{"id":12626,"date":"2024-05-31T21:42:27","date_gmt":"2024-05-31T21:42:27","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/05\/31\/t-692-05\/"},"modified":"2024-05-31T21:42:27","modified_gmt":"2024-05-31T21:42:27","slug":"t-692-05","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-692-05\/","title":{"rendered":"T-692-05"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia T-692\/05 \u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Procedencia excepcional \u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Requisitos generales y especiales de procedibilidad \u00a0<\/p>\n<p>PROCESO EJECUTIVO HIPOTECARIO-Hip\u00f3tesis jurisprudenciales que dan lugar a la terminaci\u00f3n del proceso\/PROCESO EJECUTIVO HIPOTECARIO-Terminaci\u00f3n del proceso cuando a pesar de la reliquidaci\u00f3n quedan saldos insolutos pero las partes no llegan a un acuerdo\/ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES QUE NEGARON TERMINACION DE PROCESOS HIPOTECARIOS-Procede si se utilizaron los recursos de ley dentro del proceso ejecutivo hipotecario \u00a0<\/p>\n<p>En criterio de la Corte, la terminaci\u00f3n debe operar incluso si existen saldos insolutos y si no se llega a un acuerdo sobre la reestructuraci\u00f3n de la deuda. \u00a0En este sentido, seg\u00fan la jurisprudencia que adelante se analiza, procede la terminaci\u00f3n del proceso ejecutivo hipotecario siempre que luego de efectuada la reliquidaci\u00f3n del cr\u00e9dito (a) no queden saldos a favor de la entidad financiera, (b) los saldos insolutos son cancelados por el deudor; (c) existe acuerdo de reestructuraci\u00f3n del cr\u00e9dito; (d) quedan saldos insolutos a favor de la entidad bancaria, el deudor solicita la reliquidaci\u00f3n del cr\u00e9dito pero las partes no llegan a un acuerdo sobre la reestructuraci\u00f3n del mismo. En esta \u00faltima hip\u00f3tesis, sin embargo, la Corte ha exigido que el deudor hubiere hecho uso de todos los recursos con que cuenta para la defensa de sus derechos e intereses dentro del proceso hipotecario. En efecto, desde la sentencia C-955 de 26 de julio de 2000, por medio de la cual se adelant\u00f3 el control de constitucionalidad de la Ley 546 de 1999, la Corte indic\u00f3 que la condici\u00f3n para dar por terminados los procesos ejecutivos hipotecarios en tr\u00e1mite a 31 de diciembre de 1999 era la reliquidaci\u00f3n de la deuda. En este sentido no distingui\u00f3 la hip\u00f3tesis en la cual, luego de la liquidaci\u00f3n quedaren saldos insolutos o aquella seg\u00fan la cual las partes no pudieran llegar a un acuerdo respecto de la reestructuraci\u00f3n del cr\u00e9dito. \u00a0<\/p>\n<p>PROCESO EJECUTIVO HIPOTECARIO-Alcance de la sentencia C-955\/00\/PROCESO EJECUTIVO HIPOTECARIO-Reliquidaci\u00f3n autom\u00e1tica\/PROCESO EJECUTIVO HIPOTECARIO-Terminaci\u00f3n y archivo de procesos iniciados antes del 31 de diciembre de 1999 \u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES QUE NEGARON TERMINACION DE PROCESOS HIPOTECARIOS-Improcedencia por no haber ejercido los recursos de ley o cuando el proceso comenz\u00f3 despu\u00e9s de la vigencia de la ley 546\/99. \u00a0<\/p>\n<p>La Corte ha declarado improcedente la acci\u00f3n de tutela en aquellos casos en los cuales ha encontrado que el actor dej\u00f3 de actuar diligentemente en el proceso ejecutivo o cuando a\u00fan cuenta con recursos que no ha agotado. Esto se produce, por ejemplo, cuando no se interponen los recursos ordinarios existentes, se interponen extempor\u00e1neamente. Adicionalmente, la Corte ha considerado improcedente la acci\u00f3n cuando el proceso comenz\u00f3 despu\u00e9s de la vigencia de la ley 546 de 1999 o cuando no se cumplen los presupuestos generales de aplicaci\u00f3n de dicha Ley. \u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES QUE NEGARON TERMINACION DE PROCESOS HIPOTECARIO-Juez de tutela ordena al juez de primera instancia asegurarse de la devoluci\u00f3n del inmueble \u00a0<\/p>\n<p>Para la adecuada protecci\u00f3n de los derechos del actor, el juez debe asegurarse de la devoluci\u00f3n de la casalote originalmente hipotecada al deudor y fomentar la eventual reestructuraci\u00f3n del cr\u00e9dito para intentar garantizar los fines con los cuales fue expedida la Ley 546 de 1999. Finalmente, respecto a las reclamaciones del actor sobre la reliquidaci\u00f3n del cr\u00e9dito, la Corte advierte que las mismas deben ser formuladas ante la entidad financiera, los \u00f3rganos de vigilancia y control y, si fuera el caso, el juez civil que corresponda. \u00a0<\/p>\n<p>Referencia: expedientes T-1071574 y 1069378 \u00a0<\/p>\n<p>Acci\u00f3n de tutela interpuesta por Alcides Cort\u00e9s Arias contra el Tribunal Superior de Ibagu\u00e9- Sala Civil- Familia y contra el Juzgado Primero Civil del Circuito de Espinal- Tolima y por la se\u00f1ora Rosa Elizabeth Avellaneda de Herrera contra el Juzgado Diecis\u00e9is Civil del Circuito de Bogot\u00e1. \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>Dr. JAIME C\u00d3RDOBA TRIVI\u00d1O \u00a0<\/p>\n<p>Bogot\u00e1, D.C., \u00a0primero (1\u00b0 ) de julio de dos mil cinco (2005). \u00a0<\/p>\n<p>SENTENCIA \u00a0<\/p>\n<p>Dentro del proceso de revisi\u00f3n de las decisiones dictadas por la Corte Suprema de Justicia- Sala de Casaci\u00f3n Civil y la Corte Suprema de Justicia- Sala Casaci\u00f3n Laboral, que resolvieron la acci\u00f3n de tutela promovida por el se\u00f1or Alcides Cort\u00e9s Arias contra el Tribunal Superior de Ibagu\u00e9 &#8211; Sala Civil y el Juzgado Primero Civil del Circuito de Espinal- Tolima; y de las sentencias proferidas por el Tribunal Superior de Distrito Judicial de Bogot\u00e1 &#8211; Sala Civil y la Corte Suprema de Justicia- Sala de Casaci\u00f3n Civil, que resolvieron la acci\u00f3n de tutela promovida por la se\u00f1ora Rosa Elizabeth Avellaneda de Herrera contra el Juzgado Diecis\u00e9is del Circuito de Bogot\u00e1. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. ANTECEDENTES \u00a0 \u00a0<\/p>\n<p>En auto de 18 de marzo de 2005 la Sala de Selecci\u00f3n n\u00famero 3 de la Corte Constitucional procedi\u00f3 a acumular entre si los expedientes \u00a0T-1071574 y 1069378. Se resumen a continuaci\u00f3n los antecedentes y consideraciones respectivos. \u00a0<\/p>\n<p>1. Proceso T-1071574: Alcides Cort\u00e9s Arias contra el Tribunal Superior del Distrito Judicial de Ibagu\u00e9- Sala Civil Familia y contra el Juzgado Primero Civil del Circuito de Espinal. \u00a0<\/p>\n<p>Hechos y acci\u00f3n de tutela interpuesta \u00a0<\/p>\n<p>1.1. \u00a0El 17 de noviembre de 2004 el ciudadano Alcides Cort\u00e9s Arias interpuso acci\u00f3n de tutela contra el Tribunal Superior del Distrito Judicial de Ibagu\u00e9- Sala Civil Familia y contra el Juzgado Primero Civil del Circuito de Espinal, por considerar que \u00e9stos le vulneraron sus derechos fundamentales al debido proceso (Art.29 C.P), a la igualdad (Art.13 C.P) y a una vivienda digna (Art. 51 C.P). La acci\u00f3n interpuesta se fundamenta en los siguientes hechos: \u00a0<\/p>\n<p>El d\u00eda 28 de diciembre de 1993, el se\u00f1or Alcides Cort\u00e9s Arias, celebr\u00f3 contrato de mutuo por la suma de $ 18.121.606.84 con el Banco Central Hipotecario con el prop\u00f3sito de construir su vivienda. El cr\u00e9dito fue respaldado mediante hipoteca de primer grado que reca\u00eda sobre el terreno en el cual el se\u00f1or Alcides Cort\u00e9s Arias construy\u00f3 su lugar de habitaci\u00f3n. (f.46, 47). Afirma que luego de cancelar parcialmente la deuda, el Banco interpuso proceso hipotecario en su contra, proceso que se encontraba vigente para el 31 de diciembre de 1999. Se\u00f1ala que en reiteradas oportunidades solicit\u00f3 la reliquidaci\u00f3n y reestructuraci\u00f3n del cr\u00e9dito y la terminaci\u00f3n del proceso ejecutivo, sin que el Juzgado y Tribunal demandados hubieren accedido a sus solicitudes. Indica finalmente que ha agotado todos los medios de defensa y que acude a la acci\u00f3n de tutela para que se cumpla lo dispuesto en la sentencia C-955 de 2000 de la Corte Constitucional y se ordene la terminaci\u00f3n del proceso ejecutivo.\u00a0 \u00a0<\/p>\n<p>1.2. Por las razones mencionadas, el 17 de noviembre de 2004 el se\u00f1or Cort\u00e9s Arias interpuso acci\u00f3n de tutela contra el Tribunal Superior del Distrito Judicial de Ibagu\u00e9- Sala Civil Familia y contra el Juzgado 1 Civil del Circuito de Espinal. En su escrito, manifiesta que no existen otros medios de defensa judicial, pues considera que agot\u00f3 las acciones ordinarias correspondientes sin que con ello se diera cumplimiento a lo dispuesto en el par\u00e1grafo 3 de la Ley 546 de 1999, en concordancia con la parte resolutiva de la sentencia C-955 de 2000 de la Corte Constitucional. En consecuencia, encuentra vulnerados sus derechos al debido proceso, a la defensa y a la igualdad, entre otros.\u00a0 \u00a0<\/p>\n<p>Afirma que las decisiones objeto de la acci\u00f3n presentan vicios considerados como v\u00edas de hecho de conformidad con los criterios establecidos por la Corte Constitucional en las sentencias C-543 de 1992 y T-484 de 2004. En su criterio, en el caso en concreto se incurri\u00f3 en dicha violaci\u00f3n al no dar cumplimiento a lo establecido en la ley y la jurisprudencia de la Corte Constitucional. \u00a0<\/p>\n<p>1.3. La compa\u00f1\u00eda Central de Inversiones S.A, quien es parte demandante dentro del proceso ejecutivo cuestionado, pese a informar que no fue notificada en debida forma, decide intervenir en el proceso de tutela pues la decisi\u00f3n que en este se adopte le afecta directamente. Para ilustrar al juez sobre los hechos del caso inform\u00f3 que la obligaci\u00f3n a cargo del actor presenta, para la fecha 28 de diciembre de 2004, 103 cuotas en mora y un saldo de $93.412.254.82. \u00a0<\/p>\n<p>Decisiones judiciales de instancia \u00a0<\/p>\n<p>1.4. La Corte Suprema de Justicia- Sala de Casaci\u00f3n Civil deneg\u00f3 el amparo constitucional solicitado.\u00a0 \u00a0<\/p>\n<p>Reitera que la Sala ya se ha pronunciado en ocasiones anteriores sobre este asunto, ocasiones en la cuales ha sostenido que si bien es cierto que la sentencia de tutela 606 de 2003 emanada de la Corte Constitucional parece amparar el derecho del ejecutado a la suspensi\u00f3n del proceso ejecutivo, tambi\u00e9n lo es que \u201cla situaci\u00f3n creada con esta nueva decisi\u00f3n de la Corte Constitucional, reedita problemas relativos a saber el momento en que las sentencias de constitucionalidad adquieren el car\u00e1cter de cosa juzgada, pero particularmente, sobre cuando se termina el proceso de expedici\u00f3n de dichas sentencias\u201d. Respecto a la aplicaci\u00f3n de la ley 546 de 1999 estima que \u201ccuando no hay prueba suficiente que conduzca a concluir que la obligaci\u00f3n qued\u00f3 al d\u00eda, ni que las partes comprometidas hayan convenido la refinanciaci\u00f3n de la misma, no era viable desde el punto de vista legal, dar por terminado de plano el proceso ejecutivo hipotecario con la sola presentaci\u00f3n de la reliquidaci\u00f3n y sin ninguna clase de evaluaci\u00f3n\u201d. \u00a0<\/p>\n<p>Finalmente, sostiene que en el caso bajo estudio \u201ces claro que no pod\u00eda terminarse la actuaci\u00f3n para imponer a la parte ejecutante la iniciaci\u00f3n de un nuevo proceso ejecutivo, por cuanto esta determinaci\u00f3n, solo podr\u00eda ser acordada con su acreedor la reestructuraci\u00f3n de su obligaci\u00f3n, convenio que aqu\u00ed no se acredit\u00f3; por el contrario lo que a \u00faltimo momento ha informado Central de Inversiones S.A, es que el cr\u00e9dito presenta 103 cuotas en mora\u201d \u00a0<\/p>\n<p>1.5. La Corte Suprema de Justicia- Sala de Casaci\u00f3n Laboral, confirm\u00f3 la sentencia de tutela de primera instancia. En su criterio, dado que la petici\u00f3n va encaminada a modificar una situaci\u00f3n procesal definida mediante una decisi\u00f3n judicial, \u201ccarece el juez de tutela de competencia para interferir en la tramitaci\u00f3n cuestionada.\u201d Al respecto afirma la Corte, \u201c(H)a sido un\u00e1nime y di\u00e1fana la posici\u00f3n doctrinaria asumida por esta Sala de la Corte, en el sentido de que la herramienta judicial consagrada en el art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica es un tr\u00e1mite residual y no puede ser utilizado para resolver las controversias jur\u00eddicas de los particulares entre s\u00ed, ni la de \u00e9stos con el Estado. Supondr\u00eda ello, de concebirse la tutela como acci\u00f3n paralela y concurrente, la derogaci\u00f3n de las acciones judiciales ordinarias y especiales consagradas en los c\u00f3digos y leyes procedimentales con tales prop\u00f3sitos y la sustituci\u00f3n de las jurisdicciones ordinarias y especiales por la tutela. Para estos conflictos y debates el Estado ha dispuesto una superestructura judicial, con todo su andamiaje procesal de acciones, excepciones, nulidades, incidentes y recursos, a fin de darles soluci\u00f3n eficaz bajo claras reglas de juego que aseguren un juicio imparcial y leg\u00edtimo.\u201d \u00a0<\/p>\n<p>2. Expediente T-1069378: Rosa Elizabeth Avellaneda de Herrera contra el Juzgado Diecis\u00e9is del Circuito de Bogot\u00e1 \u00a0<\/p>\n<p>Hechos y acci\u00f3n de tutela interpuesta \u00a0<\/p>\n<p>2.1. El 17 de noviembre de 2004 la ciudadana Rosa Elizabeth Avellaneda de Herrera interpuso acci\u00f3n de tutela contra el Juzgado Diecis\u00e9is del Circuito de Bogot\u00e1, por considerar que \u00e9ste le vulner\u00f3 su derecho fundamental al debido proceso (Art.29 C.P). Fundamentan su acci\u00f3n de tutela con los siguientes hechos y consideraciones: \u00a0<\/p>\n<p>La se\u00f1ora Rosa Elizabeth Avellaneda de Herrera y el se\u00f1or Jos\u00e9 Sandalio Herrera Herrera, adquirieron un pr\u00e9stamo mediante el Sistema de Cr\u00e9dito Hipotecario con el hoy Banco Comercial y de Ahorros Conavi. \u00a0<\/p>\n<p>Afirma que dentro del proceso ejecutivo impuls\u00f3 las etapas procesales necesarias para lograr la terminaci\u00f3n del proceso. As\u00ed por ejemplo, se\u00f1ala que dio contestaci\u00f3n a la demanda proponiendo las excepciones de \u201ccobro y pago de lo no debido\u201d e \u201cindebida interpretaci\u00f3n y aplicaci\u00f3n de la Ley 546 de 1999 y de la Sentencia C-955 de 2000\u201d (f.50). No obstante, en sentencia del 16 de septiembre de 2004 proferida por el Juzgado 16 Civil del Circuito de Bogot\u00e1, el Juez declar\u00f3 \u201cno probadas y por lo tanto impr\u00f3speras\u201d las excepciones presentadas por la demandada. Ordena entonces el aval\u00fao y posterior venta en p\u00fablica subasta del inmueble, propiedad de los demandados. \u00a0<\/p>\n<p>Frente a dicha sentencia los demandados presentaron el correspondiente recurso de apelaci\u00f3n. Igualmente presentaron dos recursos de reposici\u00f3n y en subsidio el de apelaci\u00f3n contra el mandamiento de pago (f.53 y 56). \u00a0<\/p>\n<p>El juez mediante auto de noviembre 5 de 2003, no repuso el mandamiento de pago, pues \u201cla reliquidaci\u00f3n del cr\u00e9dito en los t\u00e9rminos de los art\u00edculos 38 a 42 de la ley 546 de 1999, si fue practicada en el rito seg\u00fan lo deja ver, de un lado, el documento de folio 5 precedente allegado con la demanda y, de otro lado, el numeral 1\u00b0 del auto por medio del cual se inadmiti\u00f3 el libelo, en el que se orden\u00f3 a la actora explicar todo lo atinente a la mencionada reliquidaci\u00f3n\u201d. Finalmente niega el recurso de apelaci\u00f3n pues a su juicio el auto atacado no es susceptible de dicho recurso seg\u00fan lo establecido en el Art\u00edculo 505 del C.P.C modificado por el art\u00edculo 48 de la Ley 794 de 2003. \u00a0<\/p>\n<p>Informa la accionante, que paralelamente al proceso ejecutivo hipotecario, inici\u00f3 proceso ordinario \u201cpor el cobro de lo no debido\u201d contra el Banco Comercial y de Ahorros Conavi, ante el Juzgado 24 Civil Municipal de Bogot\u00e1. Dicho proceso se encuentra en etapa probatoria. \u00a0<\/p>\n<p>La accionante, manifiesta en su escrito de tutela que el Juzgado 16 Civil del Circuito de Bogot\u00e1, viola su derecho fundamental al debido proceso por la indebida interpretaci\u00f3n que hace de la Ley 546 de 1999 y la sentencia C-955 de 2000, especialmente por cuanto (1) No suspendi\u00f3 el proceso ejecutivo hipotecario \u201cno obstante haberse presentado por el demandado el inter\u00e9s de REESTRUCTURAR EL CR\u00c9DITO\u201d y (2) No cumpli\u00f3 con la suspensi\u00f3n del proceso ejecutivo de conformidad con la ley 546 de 1999 y la sentencia C-955 de 2000, que establecen que cualquier actividad procesal posterior al 31 de diciembre de 1999 \u2013 salvo la reestructuraci\u00f3n del cr\u00e9dito- est\u00e1 viciada de nulidad insubsanable. Apoya sus afirmaciones en las sentencias de la Corte Constitucional C-955 de 2000 y C-701 de 2004. \u00a0<\/p>\n<p>En virtud de lo anterior, solicita se tutele su derecho al debido proceso, y como consecuencia de ello se ordene la suspensi\u00f3n del proceso ejecutivo hipotecario que se adelanta en su contra por el Juzgado 16 Civil del Circuito de Bogot\u00e1. \u00a0<\/p>\n<p>2.2. El Juzgado 16 Civil Municipal en su respuesta a la acci\u00f3n de tutela informa que el expediente del proceso ejecutivo de la referencia, fue enviado en apelaci\u00f3n al Tribunal Superior de Distrito Judicial, corporaci\u00f3n que admiti\u00f3 dicho recurso mediante auto de 19 de noviembre de 2004 (f.49).\u00a0 \u00a0<\/p>\n<p>Decisiones judiciales de instancia \u00a0<\/p>\n<p>2.3. El Tribunal Superior de Distrito Judicial- Sala Civil neg\u00f3 el amparo constitucional solicitado. \u00a0<\/p>\n<p>Considera improcedente el mecanismo de la tutela por cuanto dentro del proceso ejecutivo se interpuso el correspondiente recurso de apelaci\u00f3n contra la sentencia proferida por el accionado el 16 de septiembre de 2004. Indica que dicho recurso se est\u00e1 tramitando ante la Sala Civil del Tribunal Superior, raz\u00f3n por la cual sostiene que la acci\u00f3n debe ser declarada improcedente, pues el Juez de tutela \u201cadem\u00e1s de no poder suplantar el juez ordinario competente para resolver, no podr\u00eda provocar decisiones paralelas sobre un mismo asunto.\u201d\u00a0 \u00a0<\/p>\n<p>2.4. La Corte Suprema de Justicia- Sala de Casaci\u00f3n Civil, confirm\u00f3 la sentencia de tutela de primera instancia. En su criterio, el asunto carece del \u201csegundo de los requisitos mencionados para la procedencia de la acci\u00f3n de tutela frente a las actuaciones judiciales\u201d, debido a que \u00a0existen mecanismos judiciales alternativos para atacar la decisi\u00f3n que se considera quebrant\u00f3 los derechos fundamentales. En consecuencia, la acci\u00f3n resulta improcedente, pues seg\u00fan el numeral 3 del art\u00edculo 86 de la Constituci\u00f3n y el art\u00edculo 6 del Decreto 2591 de 1991, la tutela es una acci\u00f3n subsidiaria y no un \u201cinstrumento alternativo o sustitutivo de los medios de defensa judiciales ordinarios\u201d.\u00a0 \u00a0<\/p>\n<p>En el caso concreto, estima la Sala \u201cest\u00e1 pendiente de desatarse por el superior funcional del juez ordinario de conocimiento y en el interior del proceso ejecutivo hipotecario el recurso de apelaci\u00f3n interpuesto contra la sentencia de primera instancia&#8230;.\u201d y por lo tanto debe negarse el amparo y confirmarse la providencia de primera instancia. \u00a0<\/p>\n<p>II. FUNDAMENTOS JURIDICOS \u00a0<\/p>\n<p>Competencia \u00a0<\/p>\n<p>1. Esta Sala es competente para revisar las decisiones proferidas dentro de las acciones de tutela de la referencia, con fundamento en el art\u00edculo 241 numeral 9 de la Constituci\u00f3n Pol\u00edtica.\u00a0 \u00a0<\/p>\n<p>Problemas jur\u00eddicos a resolver \u00a0<\/p>\n<p>2. En el presente proceso es necesario resolver tres problemas jur\u00eddicos distintos. En primer lugar es necesario definir si la acci\u00f3n de tutela procede contra sentencias judiciales. En segundo t\u00e9rmino, si esta acci\u00f3n procede contra la decisi\u00f3n judicial de no terminar el proceso ejecutivo hipotecario vigente el 31 de diciembre de 1999, cuando la persona demandada en dicho proceso solicit\u00f3 oportunamente la reliquidaci\u00f3n y reestructuraci\u00f3n del cr\u00e9dito y la suspensi\u00f3n del respetivo proceso de conformidad con lo dispuesto en la Ley 546 de 1999 y en la sentencia C-955 de 2000. \u00a0<\/p>\n<p>Procede la Corte a resolver cada uno de los asuntos planteados de conformidad con la jurisprudencia reiterada de esta misma Corporaci\u00f3n.\u00a0 \u00a0<\/p>\n<p>Tutela contra providencias judiciales: reiteraci\u00f3n de jurisprudencia \u00a0<\/p>\n<p>3. Como fue mencionado, la Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia declar\u00f3 la improcedencia de la acci\u00f3n interpuesta, con el argumento de que el juez de tutela no es competente para conocer de la acci\u00f3n de tutela contra actuaciones judiciales. Fundamenta su posici\u00f3n, entre otras razones, en la defensa de los principios de seguridad jur\u00eddica y autonom\u00eda funcional del juez y en lo dispuesto en la Sentencia C-543 de 1992 de la Corte Constitucional. \u00a0 \u00a0<\/p>\n<p>4. El argumento de la Sala de Casaci\u00f3n Laboral a favor de los principios de seguridad jur\u00eddica y autonom\u00eda funcional del juez es ampliamente compartido por la doctrina y la jurisprudencia constitucional. En efecto, como lo indica la Sala de Casaci\u00f3n Laboral, se trata de principios rectores de la administraci\u00f3n de justicia. Justamente por esta raz\u00f3n, por que se trata de principios rectores que resulta necesario resguardar, es que la Corte Constitucional ha dise\u00f1ado la teor\u00eda de la v\u00eda de hecho judicial, teor\u00eda que abre paso a la procedencia excepcional de la acci\u00f3n de tutela contra decisiones judiciales. En efecto, como se explica adelante, esta doctrina \u00a0lejos de afectar tales principios, tiende a su garant\u00eda y protecci\u00f3n. Al respecto ha dicho la Corte:\u00a0 \u00a0<\/p>\n<p>\u201c(E)n cuanto se refiere al principio de la seguridad jur\u00eddica, resulta claro que se garantiza en mucha mayor medida la seguridad de los ciudadanos sobre alcance y sentido del derecho, si existe una manera de unificar las decisiones judiciales en cada una de las distintas materias o ramas del derecho y no si su interpretaci\u00f3n se encuentra librada exclusivamente al criterio solitario e inmune de cada juez. Ese es justamente el papel de la casaci\u00f3n en materia laboral, civil o penal, el de unificar el sentido de las normas que los jueces deben aplicar para resolver las distintas controversias jur\u00eddicas. En este sentido, no debe extra\u00f1ar que en los reg\u00edmenes de control de constitucionalidad mixto \u2013 como el colombiano, el alem\u00e1n o el espa\u00f1ol \u2013 exista un recurso que, como la acci\u00f3n de tutela, permita garantizar la unidad de la interpretaci\u00f3n judicial de los derechos y las garant\u00edas fundamentales, en particular, la garant\u00eda del debido proceso constitucional. \u00a0Justamente, con este prop\u00f3sito se desarroll\u00f3 la doctrina de la v\u00eda de hecho judicial que adelante se menciona. \u00a0<\/p>\n<p>Ahora bien, para garantizar que el control judicial resulte ajustado a los principios de especializaci\u00f3n y jerarqu\u00eda, la tutela contra sentencia se debe interponer ante el superior funcional del accionado. Si se dirige contra la Corte Suprema de Justicia, el Consejo de Estado o el Consejo Superior de la Judicatura-Sala Jurisdiccional Disciplinaria, ser\u00e1 repartido a la misma corporaci\u00f3n y se resolver\u00e1 por la Sala de Decisi\u00f3n, Secci\u00f3n o Subsecci\u00f3n que corresponda. Finalmente, trat\u00e1ndose de la protecci\u00f3n de derechos constitucionales fundamentales, la Corte Constitucional tendr\u00e1 la \u00faltima palabra en tanto guardiana e interprete suprema de la Constituci\u00f3n. \u00a0<\/p>\n<p>S\u00f3lo a trav\u00e9s de un control de esta naturaleza, con un \u00fanico \u00f3rgano de cierre en materia constitucional, ser\u00e1 posible asegurar que todos los jueces de la Rep\u00fablica, obligados como est\u00e1n a aplicar la Constituci\u00f3n cuandoquiera que ello resulte conducente para resolver la respectiva causa, tengan una doctrina relativamente coherente sobre el alcance y significado de las garant\u00edas constitucionales. \u00a0De otra forma, cada juez o, en el mejor de los casos, cada jurisdicci\u00f3n, podr\u00eda tener una lectura distinta e incluso contradictoria de las disposiciones constitucionales, sin que resultara posible unificar el sentido del derecho constitucional para generar una verdadera seguridad jur\u00eddica.\u00a0 \u00a0<\/p>\n<p>Tambi\u00e9n se afirma que la violaci\u00f3n de la seguridad jur\u00eddica se produce dado que no existe un t\u00e9rmino de caducidad de la tutela contra sentencias. En consecuencia, en cualquier momento la persona que disienta de una decisi\u00f3n judicial puede impugnarla mediante la acci\u00f3n de Tutela. En este sentido, como se desarrollar\u00e1 en detalle mas adelante, es cierto que la falta de un t\u00e9rmino de caducidad puede dar lugar a la violaci\u00f3n del principio de la seguridad jur\u00eddica. Sin embargo, para conjurar este riesgo la jurisprudencia constitucional ha desarrollado la doctrina de la inmediatez. Seg\u00fan esta doctrina, la acci\u00f3n de tutela debe ser interpuesta en un t\u00e9rmino razonable y \u00a0proporcionado como mecanismo para proteger, de manera inmediata, el derecho vulnerado o amenazado. De otra forma se estar\u00eda premiando la inacci\u00f3n de la parte interesada y afectando severamente el principio universal de la seguridad jur\u00eddica, es decir, la tranquilidad que deben tener los ciudadanos sobre la estabilidad de la decisiones judiciales. Este tema ser\u00e1 desarrollado un poco mas extensamente en la pare que sigue de esta providencia.\u00a0 \u00a0<\/p>\n<p>Finalmente, se ha sostenido que se viola la seguridad jur\u00eddica y la autonom\u00eda funcional del juez por la mera posibilidad de revocar las sentencias mediante la acci\u00f3n de tutela. Este argumento llevar\u00eda a sostener que la segunda instancia es tambi\u00e9n una violaci\u00f3n de la seguridad jur\u00eddica y de la autonom\u00eda funcional, como lo seria tambi\u00e9n el recurso de casaci\u00f3n. En efecto, hasta agotar dichos recursos la sentencia no hace transito a cosa juzgada y su existencia habilita justamente al juez de alzada a revocar la decisi\u00f3n del juez de instancia y a marcar las pautas de interpretaci\u00f3n y fijaci\u00f3n del sentido del derecho. En este sentido, la tutela debe ser vista, simplemente, como un control constitucional absolutamente excepcional y de muy corta duraci\u00f3n, arbitrado por la propia Constituci\u00f3n para que en el Estado constitucional exista una cierta unidad en la interpretaci\u00f3n y aplicaci\u00f3n de las normas fundamentales y, especialmente, del debido proceso constitucional. En otras palabras, para asegurar la vigencia del principio de igualdad y del importante valor de la seguridad jur\u00eddica\u201d1.\u00a0 \u00a0<\/p>\n<p>5. Ahora bien, resta explicar la coherencia entre la decisi\u00f3n que se acaba de citar y la sentencia C-543 de 1992, as\u00ed como los desarrollos que ha tenido la doctrina de la v\u00eda de hecho en la jurisprudencia constitucional. Estos dos asuntos han sido reiteradamente explicados por la Corte. En una reciente sentencia, la Corporaci\u00f3n se\u00f1al\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cEsta doctrina constitucional ha sido precisada y reiterada en varias sentencias de unificaci\u00f3n proferidas por la Sala Plena de la Corte Constitucional. Por ejemplo, recientemente en la sentencia SU-1184 de 2001, se dijo, \u00a0<\/p>\n<p>\u2018La Corte Constitucional ha construido una nutrida l\u00ednea de precedentes en materia de tutela contra providencias judiciales, bajo las condiciones particulares de lo que se ha denominado la v\u00eda de hecho. No es de inter\u00e9s para este proceso en particular hacer un recuento de dicha l\u00ednea de precedentes. Baste considerar que sus elementos b\u00e1sicos fueron fijados en la sentencia T-231 de 1994, en la que se se\u00f1al\u00f3 que existe v\u00eda de hecho cuando se observan algunos de los cuatro defectos: sustantivo, org\u00e1nico, f\u00e1ctico y procedimental.\u2019 \u00a0<\/p>\n<p>\u201c1.3. Por lo tanto, coincide parcialmente \u00e9sta Sala de Revisi\u00f3n de la Corte Constitucional con la Sala de Casaci\u00f3n Laboral en reconocer la obligatoriedad que tienen en el sistema jur\u00eddico colombiano las sentencias de constitucionalidad, espec\u00edficamente la sentencia C-543 de 1992, pero no comparte el criterio seg\u00fan el cual en dicha sentencia se decidi\u00f3 que era contrario a la Constituci\u00f3n Pol\u00edtica de 1991 el que proceda una acci\u00f3n de tutela contra una actuaci\u00f3n judicial, incluso cuando esta configure una v\u00eda de hecho, o conlleve la amenaza de un perjuicio irremediable. \u00a0 \u00a0<\/p>\n<p>\u201cEn cambio, coincide plenamente esta Sala de Revisi\u00f3n con la decisi\u00f3n adoptada por la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia dentro del proceso T-600048, la cual, en lugar de descartar de manera absoluta la procedencia de la acci\u00f3n de tutela contra providencias judiciales, verific\u00f3 si en el caso concreto \u00e9sta era procedente. Concluy\u00f3 que no lo era y que en todo caso no se trataba de una v\u00eda de hecho. Tambi\u00e9n coincide con lo expuesto por la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia por la misma raz\u00f3n. \u00a0<\/p>\n<p>\u201cEsta Sala de Revisi\u00f3n subraya que el art\u00edculo 86 de la Constituci\u00f3n dice que la tutela procede cuando los derechos fundamentales \u201cresulten vulnerados o amenazados por la acci\u00f3n o la omisi\u00f3n de cualquier autoridad p\u00fablica\u201d. Los jueces son autoridades p\u00fablicas y sus providencias constituyen su principal forma de acci\u00f3n. \u00a0<\/p>\n<p>\u201cAdem\u00e1s, la Corte Constitucional en sus salas de revisi\u00f3n y en su Sala Plena ha reiterado que la tutela s\u00ed procede contra providencias judiciales cuando \u00e9stas constituyen v\u00edas de hecho.\u00a0 \u00a0<\/p>\n<p>\u201cNo desconoce esta Sala de Revisi\u00f3n que una sentencia, como cualquier texto, es objeto de interpretaci\u00f3n. Empero, quien interpreta con autoridad las sentencias de la Corte Constitucional es la propia Corte Constitucional, as\u00ed como esta Corporaci\u00f3n ha reconocido que qui\u00e9n interpreta con autoridad las sentencias de la Corte Suprema de Justicia es la propia Corte Suprema de Justicia, en raz\u00f3n a que su doctrina relativa al alcance de las leyes en el \u00e1mbito de su competencia como \u201cm\u00e1ximo tribunal de la jurisdicci\u00f3n ordinaria\u201d (art\u00edculo 234 C.P.), constituye un derecho viviente.2\u00a0 \u00a0<\/p>\n<p>\u201c1.4. Ahora bien, la jurisprudencia ha indicado en varias oportunidades los casos excepcionales en que el amparo procede la acci\u00f3n de tutela, indicando que se configura una v\u00eda de hecho cuando se presenta, al menos, uno de los siguientes vicios o defectos protuberantes: (1) defecto sustantivo, que se produce cuando la decisi\u00f3n controvertida se funda en una norma indiscutiblemente inaplicable; (2) defecto f\u00e1ctico, que ocurre cuando resulta indudable que el juez carece de sustento probatorio suficiente para proceder a aplicar el supuesto legal en el que se sustenta la decisi\u00f3n; (3) defecto org\u00e1nico, se presenta cuando el funcionario judicial que profiri\u00f3 la providencia impugnada, carece, absolutamente, de competencia para ello; y, (4) defecto procedimental que aparece en aquellos eventos en los que se actu\u00f3 completamente al margen del procedimiento establecido. En criterio de la Corte \u201cesta sustancial carencia de poder o de desviaci\u00f3n del otorgado por la ley, como reveladores de una manifiesta desconexi\u00f3n entre la voluntad del ordenamiento y la del funcionario judicial, aparejar\u00e1 su descalificaci\u00f3n como acto judicial.3 \u00a0<\/p>\n<p>\u201cPor otra parte, la jurisprudencia constitucional ha se\u00f1alado que aun si existen otros medios de defensa judicial para atacar una providencia judicial que incurri\u00f3 en una v\u00eda de hecho, la acci\u00f3n de tutela procede excepcionalmente cuando existe la amenaza de un perjuicio irremediable, el cual se configura cuando se dan las siguientes condiciones: (1) afecta de manera cierta y evidente sobre un derecho fundamental; (2) de ocurrir el perjuicio no existir\u00eda forma de reparar el da\u00f1o producido; (3) su ocurrencia es inminente; (4) resulta urgente la medida de protecci\u00f3n para que el sujeto supere la condici\u00f3n de amenaza en la que se encuentra; y, (5) la gravedad de los hechos es de tal magnitud que hace evidente la impostergabilidad de la tutela como mecanismo necesario para la protecci\u00f3n inmediata de los derechos constitucionales fundamentales. No obstante, en materia de tutela contra providencias judiciales la Corte ha sido estricta en impedir que dicha acci\u00f3n se emplee para eludir el procedimiento fijado en las normas legales, e inclusive, ha estimado que el recurso extraordinario de casaci\u00f3n as\u00ed como el de revisi\u00f3n, son v\u00edas id\u00f3neas cuya lentitud no justifica, por s\u00ed sola, admitir la tutela como mecanismo transitorio para evitar un perjuicio irremediable.4\u201d5 \u00a0<\/p>\n<p>La doctrina que ha sido citada resulta suficiente para desvirtuar la tesis de la Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia, en virtud de la cual resulta improcedente la acci\u00f3n de tutela contra actuaciones judiciales. En consecuencia, procede la Corte a estudiar los restantes asuntos relevantes para resolver los casos planteados.\u00a0 \u00a0<\/p>\n<p>La obligaci\u00f3n de suspender los procesos ejecutivos con t\u00edtulo hipotecario basados en un cr\u00e9dito UPAC que se encontraban en curso a 31 de diciembre de 1999: reiteraci\u00f3n de jurisprudencia \u00a0<\/p>\n<p>6. En reiterada jurisprudencia la Corte Constitucional ha sostenido que la correcta interpretaci\u00f3n del par\u00e1grafo 3 del art\u00edculo 42 de la Ley 546 de 19996 es aquella seg\u00fan la cual los procesos ejecutivos hipotecarios por deudas contra\u00eddas en upac, vigentes el 31 de diciembre de 1999, deben ser terminados luego de la correspondiente reliquidaci\u00f3n del cr\u00e9dito. En criterio de la Corte, la terminaci\u00f3n debe operar incluso si existen saldos insolutos y si no se llega a un acuerdo sobre la reestructuraci\u00f3n de la deuda. \u00a0En este sentido, seg\u00fan la jurisprudencia que adelante se analiza, procede la terminaci\u00f3n del proceso ejecutivo hipotecario siempre que luego de efectuada la reliquidaci\u00f3n del cr\u00e9dito (a) no queden saldos a favor de la entidad financiera, (b) los saldos insolutos son cancelados por el deudor; (c) existe acuerdo de reestructuraci\u00f3n del cr\u00e9dito; (d) quedan saldos insolutos a favor de la entidad bancaria, el deudor solicita la reliquidaci\u00f3n del cr\u00e9dito pero las partes no llegan a un acuerdo sobre la reestructuraci\u00f3n del mismo. En esta \u00faltima hip\u00f3tesis, sin embargo, la Corte ha exigido que el deudor hubiere hecho uso de todos los recursos con que cuenta para la defensa de sus derechos e intereses dentro del proceso hipotecario. \u00a0 \u00a0<\/p>\n<p>En efecto, desde la sentencia C-955 de 26 de julio de 2000, por medio de la cual se adelant\u00f3 el control de constitucionalidad de la Ley 546 de 1999, la Corte indic\u00f3 que la condici\u00f3n para dar por terminados los procesos ejecutivos hipotecarios en tr\u00e1mite a 31 de diciembre de 1999 era la reliquidaci\u00f3n de la deuda. En este sentido no distingui\u00f3 la hip\u00f3tesis en la cual, luego de la liquidaci\u00f3n quedaren saldos insolutos o aquella seg\u00fan la cual las partes no pudieran llegar a un acuerdo respecto de la reestructuraci\u00f3n del cr\u00e9dito. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>En criterio de la Corte, dado que la crisis en el sistema de vivienda tiene origen en el colapso generalizado del sistema de financiaci\u00f3n y no en el simple incumplimiento de los deudores, resultaba necesario que los alivios que la ley establec\u00eda se correspondieran con la suspensi\u00f3n de los procesos ejecutivos. Por consideraciones relativas al principio de igualdad, la Corte declar\u00f3 inexequible el plazo de 90 d\u00edas que establec\u00eda el par\u00e1grafo 3 del art\u00edculo 42 de la ley 546 de 1999, para acogerse a la reliquidaci\u00f3n del cr\u00e9dito y solicitar la terminaci\u00f3n del proceso. De igual manera, declar\u00f3 inexequible el inciso final del par\u00e1grafo en comento, que consagraba la posibilidad de reanudar el proceso ejecutivo en la etapa en la que se encontraba el proceso suspendido si dentro del a\u00f1o siguiente el deudor incurre nuevamente en mora. Al respecto dijo la Corte:\u00a0 \u00a0<\/p>\n<p>\u201c En ese orden de ideas, la suspensi\u00f3n de los procesos en curso, ya por petici\u00f3n del deudor, o por decisi\u00f3n adoptada de oficio por el juez, tiene por objeto que se efect\u00fae la reliquidaci\u00f3n del cr\u00e9dito y, producida ella, debe dar lugar a la terminaci\u00f3n del proceso y a su archivo sin m\u00e1s tr\u00e1mite, como lo ordena la norma, que en tal sentido, lejos de vulnerar, desarrolla el postulado constitucional que propende al establecimiento de un orden justo (Pre\u00e1mbulo y art\u00edculo 2 C.P.) y realiza los principios de prevalencia del derecho sustancial (art. 228 C.P.) y de acceso a la administraci\u00f3n de justicia (art. 229 C.P.). \u00a0<\/p>\n<p>Empero, esos mismos prop\u00f3sitos del legislador, y por consiguiente las normas constitucionales que los contemplan, aparecen desvirtuados por el par\u00e1grafo que se estudia cuando supedita la suspensi\u00f3n del proceso a que el deudor decida acogerse a la reliquidaci\u00f3n de su cr\u00e9dito dentro de los noventa d\u00edas siguientes a la entrada en vigencia de la Ley. Por una parte, ese t\u00e9rmino es inconstitucional por las razones atr\u00e1s expuestas, y de otro lado, si las condiciones objetivas que deben dar lugar a la mencionada suspensi\u00f3n no dependen de haberse acogido o no a una reliquidaci\u00f3n a la que todos los deudores ten\u00edan derecho, se trata de un requisito que rompe la igualdad y que injustificadamente condena a una persona, adem\u00e1s de no recibir oportunamente el abono que le corresponde, a no poder efectuar la compensaci\u00f3n entre el abono y lo que debe, y muy probablemente a ser condenada en el proceso. \u00a0<\/p>\n<p>Tambi\u00e9n contraviene el derecho a la igualdad, el debido proceso y el derecho a la administraci\u00f3n de justicia la parte final del mismo par\u00e1grafo 3, a cuyo tenor, si dentro del a\u00f1o siguiente a la reestructuraci\u00f3n del cr\u00e9dito el deudor incurriere nuevamente en mora, los procesos se reiniciar\u00e1n a solicitud de la entidad financiera y con la sola demostraci\u00f3n de la mora, en la etapa en que se encontraban al momento de la suspensi\u00f3n, y previa actualizaci\u00f3n de su cuant\u00eda. \u00a0<\/p>\n<p>En efecto, es evidente que se trata de situaciones jur\u00eddicas distintas, en cuanto la nueva mora, que al tenor del precepto se constituye en hip\u00f3tesis de la reanudaci\u00f3n del proceso, debe dar lugar a un proceso nuevo y de ninguna manera acumularse a la que hab\u00eda propiciado el anterior, terminado, seg\u00fan el mismo mandato legal, con las consecuencias que tiene la terminaci\u00f3n de todo juicio. \u00a0<\/p>\n<p>El acreedor goza, por supuesto, del derecho a iniciar un nuevo proceso ejecutivo en contra de su deudor, pero mal puede retomarse el proceso expirado, en la etapa en que se encontraba cuando se produjo la suspensi\u00f3n, puesto que ello significa atribuir efectos ultra activos a situaciones previas ya definidas, combin\u00e1ndolas con hechos nuevos, en contra de una de las partes, con notorio desequilibrio en la relaci\u00f3n procesal\u201d \u00a0<\/p>\n<p>En virtud de la sentencia comentada, el texto de la norma demandada quedo como sigue (se subrayan los apartes declarados inconstitucionales):\u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 3. Los deudores cuyas obligaciones se encuentren vencidas y sobre las cuales recaigan procesos judiciales que dentro de los noventa (90) d\u00edas siguientes a la entrada en vigencia de la presente ley decidan acogerse a la reliquidaci\u00f3n de su cr\u00e9dito hipotecario, tendr\u00e1n derecho a solicitar suspensi\u00f3n de los mencionados procesos. Dicha suspensi\u00f3n podr\u00e1 otorgarse autom\u00e1ticamente por el juez respectivo. En caso de que el deudor acuerde dentro del plazo la reliquidaci\u00f3n de su obligaci\u00f3n, de conformidad con lo previsto en este art\u00edculo el proceso se dar\u00e1 por terminado y se proceder\u00e1 a su archivo sin m\u00e1s tr\u00e1mite. Si dentro del a\u00f1o siguiente a la reestructuraci\u00f3n del cr\u00e9dito el deudor incurriere nuevamente en mora, los procesos se reiniciar\u00e1n a solicitud de la entidad financiera y con la sola demostraci\u00f3n de la mora, en la etapa en que se encontraban al momento de la suspensi\u00f3n, y previa actualizaci\u00f3n de su cuant\u00eda\u201d. \u00a0<\/p>\n<p>Posteriormente, en las sentencias T-606 de 2003 y T-701 de 2004, la Corte entendi\u00f3 que la terminaci\u00f3n del proceso ejecutivo hipotecario, una vez producida la reliquidaci\u00f3n de la obligaci\u00f3n, era la interpretaci\u00f3n m\u00e1s correcta del texto legal vigente luego de la sentencia C-955 de 2000. En consecuencia, la Corte neg\u00f3 la solicitud de las entidades financieras de declarar como v\u00eda de hecho las decisiones de jueces civiles que hab\u00edan dado por terminados los procesos ejecutivos hipotecarios vigentes a 31 de diciembre de 1999 incluso en aquellos casos en los cuales, luego de la reliquidaci\u00f3n del cr\u00e9dito, quedaba un saldo por pagar y las partes no llegaban a un acuerdo de reestructuraci\u00f3n.\u00a0 \u00a0<\/p>\n<p>Al respecto, en la sentencia T-701, en la cual la Corporaci\u00f3n estudiaba si una decisi\u00f3n judicial que daba por terminado el proceso ejecutivo luego de la reliquidaci\u00f3n del cr\u00e9dito era una v\u00eda de hecho, \u00a0dijo la Corte:\u00a0 \u00a0<\/p>\n<p>En el mismo sentido, en las sentencias T-199 de 2005, T-258 de 2005, T-282 de 2005, T-357 de 2005 y T-391 de 2005, la Corte ha se\u00f1alado que existe v\u00eda de hecho judicial por defecto sustantivo en aquellos casos en los cuales los jueces civiles omiten decretar la terminaci\u00f3n del proceso ejecutivo hipotecario vigente a 31 de diciembre de 1999, cuando se ha solicitado la reliquidaci\u00f3n del cr\u00e9dito para vivienda adquirido previamente. Al respecto, en la sentencia T-199 de 2005 dijo la Corte:\u00a0 \u00a0<\/p>\n<p>\u201cEn efecto, dicho derecho fundamental \u2013 el derecho al debido proceso &#8211; fue ostensiblemente vulnerado por las decisiones tanto del Juez de ejecuci\u00f3n, como de la Sala Civil del Tribunal Superior de Medell\u00edn, pues ellas desconocieron los efectos procesales resultantes de la reliquidaci\u00f3n del cr\u00e9dito, que consist\u00edan en la terminaci\u00f3n del proceso y su archivo sin m\u00e1s tr\u00e1mites. Con ello se apartaron infundadamente de lo dispuesto por la ley, concretamente de lo reglado actualmente por el par\u00e1grafo 3\u00b0 del art\u00edculo 42 de la Ley 546 de 1999, y de la jurisprudencia vertida al respecto por esta Corporaci\u00f3n, incurriendo en una v\u00eda de hecho por defecto sustantivo. Efectivamente, la Corte ha venido explicando por qu\u00e9 este alejamiento injustificado del texto de la ley y de los precedentes jurisprudenciales en materia constitucional se erige en una decisi\u00f3n caprichosa que no puede ser tenida en cuenta como ajustada a derecho, sino m\u00e1s bien como una verdadera v\u00eda de hecho. (&#8230;) As\u00ed pues, como lo dijera el magistrado disidente de la Sala Civil del h. Tribunal Superior de Medell\u00edn, dentro del tr\u00e1mite del proceso ejecutivo ha debido tenerse en cuenta lo reglado por el par\u00e1grafo 3\u00b0 del art\u00edculo 42 de la Ley 546 de 1999, as\u00ed como la jurisprudencia referente a la terminaci\u00f3n del proceso por reliquidaci\u00f3n del cr\u00e9dito que dicha norma prescribe. Sin necesidad de entrar a establecer si dicha liquidaci\u00f3n se ajustaba a la ley, tan pronto la misma se produjo debi\u00f3 haberse ordenado la terminaci\u00f3n del proceso. Como no se procedi\u00f3 as\u00ed, se incurri\u00f3 en v\u00eda de hecho por defecto sustantivo y en violaci\u00f3n del derecho al debido proceso de los aqu\u00ed demandantes.\u201d.\u00a0 \u00a0<\/p>\n<p>En el mismo sentido de las sentencia antes citadas, la Sala de lo Contencioso Administrativo del Consejo de Estado ha considerado que \u201cseg\u00fan lo establecido en el par\u00e1grafo 3 del art\u00edculo 42 de la Ley 546 de 1999 y de conformidad con la sentencia C-599 de 26 de julio de 2000 dictada por la Corte Constitucional, producida la reliquidaci\u00f3n del cr\u00e9dito debi\u00f3 terminarse el proceso y proceder a su archivo, sin m\u00e1s tr\u00e1mite\u201d7.\u00a0 \u00a0<\/p>\n<p>Ahora bien, la Corte ha declarado improcedente la acci\u00f3n de tutela en aquellos casos en los cuales ha encontrado que el actor dej\u00f3 de actuar diligentemente en el proceso ejecutivo o cuando a\u00fan cuenta con recursos que no ha agotado. Esto se produce, por ejemplo, cuando no se interponen los recursos ordinarios existentes, se interponen extempor\u00e1neamente8. Adicionalmente, la Corte ha considerado improcedente la acci\u00f3n cuando el proceso comenz\u00f3 despu\u00e9s de la vigencia de la ley 546 de 1999 o cuando no se cumplen los presupuestos generales de aplicaci\u00f3n de dicha Ley9. \u00a0<\/p>\n<p>Estudio del caso concreto. Expediente 1071574 \u00a0<\/p>\n<p>7. En virtud de las reglas mencionadas anteriormente, resulta necesario ahora verificar si, en el presente caso, se cumplen los requisitos de procedibilidad de la acci\u00f3n de tutela y si la Corte debe proceder a tutelar el derecho al debido proceso presuntamente vulnerado. Para poder efectuar la verificaci\u00f3n de los requisitos de procedibilidad de la tutela la Corte solicit\u00f3 algunas pruebas que le permitieron conocer la siguiente informaci\u00f3n: \u00a0<\/p>\n<p>El 28 de diciembre de 1993, el se\u00f1or Alcides Cort\u00e9s Arias, celebr\u00f3 contrato de mutuo por la suma de $ 18.121.606.84 con el Banco Central Hipotecario con el prop\u00f3sito de construir su vivienda. El cr\u00e9dito fue respaldado mediante hipoteca de primer grado que reca\u00eda sobre el terreno en el cual el se\u00f1or Alcides Cort\u00e9s Arias construy\u00f3 su lugar de habitaci\u00f3n. \u00a0<\/p>\n<p>Al transcurrir el tiempo, el se\u00f1or Cort\u00e9s Arias incurri\u00f3 en mora en el pago de sus cuotas. En raz\u00f3n de la mora presentada, el Banco Central Hipotecario interpuso demanda ejecutiva ante el Juzgado Primero Civil del Circuito del Espinal- Tolima, quien libr\u00f3 mandamiento de pago y orden\u00f3 el embargo del bien objeto de hipoteca, medida que se formaliz\u00f3 el 13 de diciembre de 1994. El 14 de julio de 1995 se present\u00f3 liquidaci\u00f3n del cr\u00e9dito por parte del Banco Central Hipotecario. El 25 de septiembre de 1995, dando cumplimiento a lo ordenado por el juzgado el 23 de agosto de 1995, se rindi\u00f3 \u00a0dictamen de aval\u00fao del inmueble embargado. El demandado no present\u00f3 objeciones a dicho aval\u00fao. El 26 de octubre de 1995 se fij\u00f3 fecha para el remate, pero previo acuerdo las partes solicitaron la suspensi\u00f3n del proceso por el t\u00e9rmino de 3 meses y se hizo entrega en calidad de dep\u00f3sito provisional al se\u00f1or Alcides Cort\u00e9s del inmueble. No obstante, ante el incumplimiento parcial del deudor, el 3 de septiembre de 1996, el Banco Central Hipotecario solicit\u00f3 el levantamiento de la suspensi\u00f3n del proceso. Los d\u00edas 11 de marzo, 12 de septiembre de 1997 y 6 de octubre de 1999, se realizaron las diligencias de remate a las cuales no se present\u00f3 postor alguno. Como consecuencia de esto el Banco solicit\u00f3 el d\u00eda 13 de octubre de 1999, le fuera adjudicado el inmueble objeto de hipoteca. (f.196). El 30 de junio de 1999 el apoderado del se\u00f1or Alcides Cort\u00e9s Arias, inici\u00f3 tramite incidental para que se declarara la nulidad procesal por falta de las formalidades prescritas para realizar el remate del bien. El juez neg\u00f3 tal solicitud por considerar que fue presentada fuera de t\u00e9rmino, ante lo cual el apoderado interpuso recurso de apelaci\u00f3n que se surti\u00f3 ante el Tribunal Superior de Ibagu\u00e9, quien confirm\u00f3 la decisi\u00f3n. \u00a0<\/p>\n<p>El 19 de enero de 2000, le fue adjudicado el inmueble al Banco Central Hipotecario (f.206). \u00a0 \u00a0<\/p>\n<p>Una vez notificada la anterior decisi\u00f3n, el 31 de enero de 2000, el demandado alleg\u00f3 al juzgado escrito del derecho de petici\u00f3n presentado al Banco Central Hipotecario, solicitando reliquidaci\u00f3n del cr\u00e9dito teniendo en cuenta la Ley 546 de 1999 y lo dispuesto por la Corte Constitucional. (f.224). Adicionalmente, presentaba las bases para la reestructuraci\u00f3n del cr\u00e9dito y solicitaba al juzgado la terminaci\u00f3n y archivo del proceso ejecutivo. \u00a0<\/p>\n<p>Dado que no recibi\u00f3 respuesta a su solicitud, el 7 de julio de 2000 el se\u00f1or Cort\u00e9s Arias solicit\u00f3 a la Superintendencia la reversi\u00f3n de la negociaci\u00f3n de adjudicaci\u00f3n del inmueble a favor del Banco Central Hipotecario y que se practicara la liquidaci\u00f3n del cr\u00e9dito por parte de esta entidad. (Escrito con copia al Juzgado Civil de Circuito de Espinal) (f.241). Adicionalmente, el 27 de julio de 2000 el se\u00f1or Cort\u00e9s Arias, alleg\u00f3 al expediente copia de un derecho de petici\u00f3n presentado a la Corte Constitucional solicitando la revisi\u00f3n del proceso y la reliquidaci\u00f3n \u00a0del cr\u00e9dito. (f.231) \u00a0<\/p>\n<p>El 7 de septiembre de 2000, nuevamente, el apoderado del demandado present\u00f3 escrito solicitando la suspensi\u00f3n del proceso y la reliquidaci\u00f3n del cr\u00e9dito seg\u00fan los par\u00e1metros se\u00f1alados por la Corte Constitucional. (f.255). Como respuesta a esta solicitud, el 20 de septiembre del mismo a\u00f1o, el juez ordena suspender el proceso y le fija al Banco 30 d\u00edas para la reliquidaci\u00f3n del cr\u00e9dito. Adicionalmente, suspende el cumplimiento de la decisi\u00f3n de 19 de enero.\u00a0 \u00a0<\/p>\n<p>El 8 de julio de 2001 se present\u00f3 por parte del Banco la reliquidaci\u00f3n del cr\u00e9dito. El apoderado del demandado solicit\u00f3 la aclaraci\u00f3n de la reliquidaci\u00f3n.(f.273). Debido a que el Banco Central Hipotecario, vendi\u00f3 su cartera a la Compa\u00f1\u00eda Central de Inversiones S.A, fueron estos quienes aclararon la reliquidaci\u00f3n, anexando el movimiento hist\u00f3rico de pago del demandado. (f.283 y ss) \u00a0<\/p>\n<p>El 19 de octubre de 2001 el apoderado del se\u00f1or Alcides Cort\u00e9s solicit\u00f3 la nulidad \u201ca partir del momento en que debi\u00f3 decretarse la suspensi\u00f3n del proceso con el fin de que la corporaci\u00f3n efect\u00fae la reliquidaci\u00f3n del cr\u00e9dito, de acuerdo a los fallos de la Corte Constitucional\u201d. (f.41 cuaderno 5). La anterior solicitud fue rechazada por el Juzgado pues consider\u00f3 que \u00a0se \u201cremedi\u00f3 o cumpli\u00f3 con la suspensi\u00f3n de ley, siendo distinto que a\u00fan no se haya tomado decisi\u00f3n de fondo&#8230;\u201d. En consecuencia, orden\u00f3 correr traslado al demandado de la reliquidaci\u00f3n del cr\u00e9dito, para que se pronunciara al respecto. \u00a0<\/p>\n<p>La reliquidaci\u00f3n fue objetada por el apoderado del demandado (f.57 cuaderno 5) quien adicionalmente interpuso recurso de reposici\u00f3n y en subsidio el de apelaci\u00f3n frente al auto que le neg\u00f3 la nulidad (f.65 cuaderno 5). El Juzgado Civil del Circuito no repuso el auto y concedi\u00f3 el recurso de apelaci\u00f3n, el cual se surti\u00f3 ante el Tribunal Superior- Sala Civil Familia. \u00a0<\/p>\n<p>El 14 de marzo de 2003, se notific\u00f3 al juzgado de la admisi\u00f3n de la acci\u00f3n de tutela interpuesta por el se\u00f1or Alcides Cort\u00e9s Arias contra el Juzgado Primero Civil del Circuito del Espinal. (f.323). No obstante, dicha acci\u00f3n de tutela fue denegada en primera y segunda instancia, porque los jueces de tutela consideraron que el accionado \u201corden\u00f3 la suspensi\u00f3n del proceso con el fin de que la entidad acreedora presentara la reliquidaci\u00f3n del cr\u00e9dito.\u201d Adicionalmente, porque en el momento de decidir la acci\u00f3n de tutela, la reliquidaci\u00f3n presentada por la entidad ejecutante, hab\u00eda sido objetada por el accionante, sin que se hubiera resuelto sobre la misma.10 \u00a0<\/p>\n<p>El Tribunal Superior- Sala Civil Familia confirm\u00f3 la decisi\u00f3n del a- quo. Como consecuencia de lo anterior el apoderado interpuso el recurso de S\u00faplica, el cual fue negado por improcedente.(f.19) \u00a0<\/p>\n<p>El 24 de junio de 2003 se orden\u00f3 la entrega del inmueble a la entidad demandante (f.327). Diligencia que se realiz\u00f3 el d\u00eda 25 de noviembre de 2003, pero que se suspendi\u00f3, para que el demandante procediera a desocupar el inmueble. \u00a0<\/p>\n<p>El 13 de enero de 2004, el nuevo apoderado del demandante dentro del proceso ejecutivo inici\u00f3 incidente de nulidad para que se decretara la terminaci\u00f3n del proceso, seg\u00fan lo establecido en la sentencia de la Corte Constitucional C-955 de 2000. (f.2 cuaderno 6). El juzgado declar\u00f3 no prospero el incidente, ante lo cual el apoderado del demandado interpuso apelaci\u00f3n. El recurso se desat\u00f3 ante el Tribunal Superior- Sala Civil Familia, que en decisi\u00f3n del 12 de octubre de 2004 confirm\u00f3 la decisi\u00f3n del juez de instancia. En consecuencia, el juzgado fij\u00f3 el 24 de septiembre de 2004 como fecha para la realizaci\u00f3n de la entrega definitiva del inmueble por parte del se\u00f1or Alcides Castro Arias al Banco Central Hipotecario. (f.415) \u00a0<\/p>\n<p>Para el momento de la interposici\u00f3n de la acci\u00f3n de tutela, el cr\u00e9dito adquirido por valor de 18.121.606.84 pesos, se hab\u00eda convertido en una deuda de 93.412.254.82 pesos, pese a que el actor hab\u00eda cancelado sumas adicionales cercanas a los 36 millones de pesos. De otra parte, la casa lote hipotecada en la cual habita, parec\u00eda entonces tener un valor comercial real menor al valor nominal del cr\u00e9dito originalmente otorgado. \u00a0 \u00a0<\/p>\n<p>8. Como puede observarse en el recuento anterior, en el presente caso el actor solicit\u00f3 un cr\u00e9dito para vivienda en el a\u00f1o de 1993. Dado que dej\u00f3 de pagar las cuotas correspondientes, la entidad financiera prestataria interpuso contra \u00e9l un proceso ejecutivo que se encontraba vigente el 31 de diciembre de 1999. El 31 de enero del a\u00f1o 2000 el actor solicit\u00f3 la reliquidaci\u00f3n del cr\u00e9dito, la reestructuraci\u00f3n del mismo y la terminaci\u00f3n del proceso ejecutivo. Tal y como consta en el expediente, esta solicitud se repite insistentemente a lo largo de todo el proceso mediante la interposici\u00f3n de todos los recursos a su alcance e incluso mediante el env\u00edo de solicitudes informales tanto al juzgado como a la entidad financiera. Incluso interpuso, antes del agotamiento pleno de aquellos, una acci\u00f3n de tutela que \u00a0fue declarada improcedente dado que para entonces a\u00fan exist\u00edan a disposici\u00f3n del actor recursos ordinarios dentro del proceso. \u00a0\u00a0 \u00a0<\/p>\n<p>No obstante lo anterior, s\u00f3lo hasta el 8 de julio de 2001 la entidad financiera accedi\u00f3 a la reliquidaci\u00f3n del cr\u00e9dito luego de lo cual el juez continu\u00f3 el tr\u00e1mite del proceso ejecutivo hasta la entrega final del inmueble.\u00a0 \u00a0<\/p>\n<p>Como resulta claro del recuento de los hechos que aparecen en el expediente, hasta el \u00faltimo momento antes de la entrega material del inmueble a la entidad financiera, el actor solicit\u00f3 la reestructuraci\u00f3n del cr\u00e9dito y la terminaci\u00f3n del proceso ejecutivo. \u00a0<\/p>\n<p>9. Tal y como fue explicado en un aparte anterior de esta providencia, ante las \u00a0insistentes solicitudes del \u00a0actor, lo que proced\u00eda era la oportuna reliquidaci\u00f3n del cr\u00e9dito \u2013 la que tard\u00f3 mas de un a\u00f1o y medio en producirse \u2013 la promoci\u00f3n de la reestructuraci\u00f3n de la deuda y la terminaci\u00f3n del proceso ejecutivo. Sin embargo, el juez admiti\u00f3 la mora de mas de un a\u00f1o en la entrega de la reliquidaci\u00f3n del cr\u00e9dito y una vez recibida continu\u00f3 el proceso ejecutivo que culmin\u00f3 con la entrega material del bien a la entidad financiera en noviembre de 2004, poco tiempo despu\u00e9s de interpuesta la acci\u00f3n de tutela que se analiza.\u00a0 \u00a0<\/p>\n<p>En estas condiciones, la Corte debe proceder a tutelar el derecho del actor al debido proceso y, en consecuencia, ordenar\u00e1 que se decrete la nulidad de todo lo actuado en el proceso ejecutivo hipotecario seguido en contra del actor, a partir de la entrega de la reliquidaci\u00f3n del cr\u00e9dito por pare de la entidad financiera y la terminaci\u00f3n del mismo a partir de la misma fecha. \u00a0En todo caso, para la adecuada protecci\u00f3n de los derechos del \u00a0actor, el juez debe asegurarse de la devoluci\u00f3n de la casalote originalmente hipotecada al deudor y fomentar la eventual reestructuraci\u00f3n del cr\u00e9dito para intentar garantizar los fines con los cuales fue expedida la Ley 546 de 1999. \u00a0Finalmente, respecto a las reclamaciones del actor sobre la reliquidaci\u00f3n del cr\u00e9dito, la Corte advierte que las mismas deben ser formuladas ante la entidad financiera, los \u00f3rganos de vigilancia y control y, si fuera el caso, el juez civil que corresponda. \u00a0 \u00a0<\/p>\n<p>Estudio del Caso concreto. Expediente T-1069378\u00a0 \u00a0<\/p>\n<p>10. En este caso igualmente deber\u00e1 verificarse \u00a0si se dan los supuestos para que proceda la acci\u00f3n de tutela y si la Corte debe tutelar el derecho al debido proceso presuntamente vulnerado. De las pruebas recaudadas se puede obtener la siguiente informaci\u00f3n.\u00a0 \u00a0<\/p>\n<p>Para la \u00e9poca en que se adelantaron las diligencias de notificaci\u00f3n del mandamiento de pago (15 de octubre de 2003 f.60) y se procedi\u00f3 a dictar sentencia, el art\u00edculo 42 de la ley 546 ya hab\u00eda sido objeto del control de constitucionalidad, fij\u00e1ndose en la Sentencia C-955 de 26 de julio de 2000 y en distintos pronunciamientos de tutela (SU- 846 de 2000 y T-606 de 2003), la forma como dicha norma deb\u00eda interpretarse. Dentro del proceso ejecutivo hipotecario la demandada impuls\u00f3 las etapas procesales necesarias para lograr la terminaci\u00f3n del proceso y la reliquidaci\u00f3n del cr\u00e9dito de conformidad con su interpretaci\u00f3n de las normas aplicables. As\u00ed por ejemplo, contest\u00f3 la demanda y propuso las excepciones de \u201ccobro y pago de lo no debido\u201d e \u201cindebida interpretaci\u00f3n y aplicaci\u00f3n de la ley 546 de 1999 y de la Sentencia C-955 de 2000\u201d. Igualmente present\u00f3 recurso de reposici\u00f3n y en subsidio el de apelaci\u00f3n contra el mandamiento de pago (f.53 y 56). El juez de la causa, mediante auto de noviembre 5 de 2003, no repuso el mandamiento de pago. Finalmente niega el recurso de apelaci\u00f3n pues a su juicio el auto atacado no es susceptible de dicho recurso seg\u00fan lo establecido en el Art\u00edculo 505 del C.P.C modificado por el art\u00edculo 48 de la Ley 794 de 2003. \u00a0<\/p>\n<p>En sentencia del 16 de septiembre de 2004 proferida por el Juzgado 16 Civil del Circuito de Bogot\u00e1, el Juez declar\u00f3 \u201cno probadas y por lo tanto impr\u00f3speras\u201d las excepciones presentadas por la demandada. \u00a0En consecuencia decret\u00f3 el aval\u00fao y venta en p\u00fablica subasta del inmueble propiedad de la actora. \u00a0Frente a dicha sentencia la actora present\u00f3 el correspondiente recurso de apelaci\u00f3n.(f.69). La Corte procedi\u00f3 a constatar si el recurso \u00a0de apelaci\u00f3n hab\u00eda sido resuelto en sentido de confirmar la sentencia impugnada o, por el contrario, acceder a las pretensiones de la actora. En virtud de tales averiguaciones pudo constatar que el d\u00eda 4 de marzo de 2005 el Tribunal Superior de Distrito Judicial de Bogot\u00e1- Sala Civil confirm\u00f3 la sentencia del Juzgado 16 Civil de Circuito del 16 de septiembre de 2004. \u00a0<\/p>\n<p>Ahora bien, de los hechos anteriormente mencionados resulta que en el presente caso no esta claro cu\u00e1ndo comenz\u00f3 el proceso ejecutivo hipotecario cuya sentencia dio lugar a la acci\u00f3n de tutela. Tampoco existe total claridad sobre si el juez civil de la causa cumpli\u00f3 con lo establecido en la ley y la Constituci\u00f3n pese a lo cual proced\u00eda leg\u00edtimamente la sentencia ejecutiva impugnada. Tales datos no se han podido constatar dado que la Corte no conoce el expediente judicial que se encontraba en tramite de apelaci\u00f3n. En consecuencia y dado que fue resuelto negativamente el recurso de apelaci\u00f3n interpuesto, la Corte proceder\u00e1 a desacumular los dos procesos estudiados y a solicitar las pruebas que requiere para proceder a adoptar una decisi\u00f3n de fondo dentro del expediente T-1069378. \u00a0 \u00a0<\/p>\n<p>III. DECISI\u00d3N\u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Cuarta de Revisi\u00f3n de la Corte Constitucional, administrando justicia en nombre del Pueblo y por mandato de la Constituci\u00f3n, \u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>Primero: DESACUMULAR los expedientes T-1071574 y T-1069378. \u00a0<\/p>\n<p>Segundo: REVOCAR las sentencias proferidas el 3 de diciembre de 2004 y el 5 de febrero de 2005, por la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia y la Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia, respectivamente, dentro del proceso iniciado por Alcides Cort\u00e9s Arias contra el Tribunal Superior de Ibagu\u00e9 &#8211; Sala Civil y el Juzgado Primero Civil del Circuito de Espinal. \u00a0<\/p>\n<p>Tercero: ORDENAR al se\u00f1or Juez Primero Civil del Circuito de Espinal, que en el t\u00e9rmino de tres d\u00edas siguientes a la notificaci\u00f3n de la presente sentencia, decrete la nulidad de lo actuado en el proceso ejecutivo hipotecario instaurado por el Banco Central Hipotecario \u00a0contra Alcides Cort\u00e9s Arias, a partir del 8 de julio de 2001, fecha en la cual se adjunt\u00f3 al expediente la reliquidaci\u00f3n del cr\u00e9dito por parte de la entidad financiera demandante. Adicionalmente, para garantizar la protecci\u00f3n integral del derecho al debido proceso del actor, el se\u00f1or Juez Primero Civil del Circuito de Espinal deber\u00e1 asegurarse de que la entidad financiera regrese al actor la casa lote hipotecada y entregada a dicha entidad en diligencia de noviembre de 2004, y fomentar una eventual reestructuraci\u00f3n del cr\u00e9dito.\u00a0 \u00a0<\/p>\n<p>Cuarto: Por Secretar\u00eda General l\u00edbrense las comunicaciones previstas en el art\u00edculo 36 del Decreto Ley 2591 de 1991. \u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese, publ\u00edquese en la Gaceta de la Corte Constitucional y c\u00famplase \u00a0<\/p>\n<p>JAIME C\u00d3RDOBA TRIVI\u00d1O \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>Presidente de la Sala \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>MARCO GERARDO MONROY CABRA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0<\/p>\n<p>Secretaria General \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 T-315 de 2005. \u00a0<\/p>\n<p>2 En la sentencia C-557 de 2001 se consider\u00f3 al respecto lo siguiente: \u201cSi bien el control de constitucionalidad de las normas es un control abstracto porque no surge de su aplicaci\u00f3n en un pro\u00adceso particular, ello no significa que el juicio de exequibilidad deba efectuarse sin tener en cuenta el con\u00adtexto dentro del cual la norma fue creada (i.e. su nacimiento), y dentro del cual ha sido interpretada (i.e. ha vi\u00advido). En fin: en buena medida, el sentido de toda norma jur\u00eddica depende del contexto dentro del cual es aplicada. || Ahora, dentro de las m\u00faltiples dimensiones de ese contexto \u2013bien sea la ling\u00fc\u00edstica, que permite fijar su sentido natural, o bien la sociol\u00f3gica, que hace posible apreciar sus funciones reales- se destaca la actividad de los expertos que han interpretado los conceptos t\u00e9cnicos que ella contiene y que los han aplicado a casos concretos. Obviamente, esos expertos son los jueces y los doctrinantes especializados en la materia tratada en la norma; dentro de ellos, una posici\u00f3n preeminente la ocupan los \u00f3rganos judiciales colegiados que se encuentran en la cima de una jurisdicci\u00f3n. As\u00ed lo ha establecido la Constituci\u00f3n al definir al Consejo de Estado como \u201ctribunal supremo de lo contencioso administrativo\u201d (art. 237- 1 de la CP) y a la Corte Suprema de Justicia como \u201cm\u00e1ximo tribunal de la jurisdicci\u00f3n ordinaria\u201d (art. 234 de la CP). Por lo tanto, la jurisprudencia de ambos \u00f3rganos es un referente indispensable para apreciar el significado viviente de las normas demandadas. Al prestarles la atenci\u00f3n que su ubicaci\u00f3n institucional exige, la Corte Constitucional est\u00e1 valorando su labor hermen\u00e9utica dentro de un mismo sistema jur\u00eddico. Obviamente, cuando no exista jurisprudencia sobre las normas objeto del control constitucional, la Corte Constitucional tendr\u00e1 que acudir a otras fuentes del derecho para interpretar los art\u00edculos demandados.\u201d \u00a0<\/p>\n<p>3 Sentencia T-231\/94\u00a0 \u00a0<\/p>\n<p>4 Sentencia SU-1299\/01 \u00a0y las dem\u00e1s sentencias de unificaci\u00f3n all\u00ed resumidas. \u00a0<\/p>\n<p>5 Sentencia T-057\/2004 \u00a0<\/p>\n<p>6 \u201cLa Ley 546 de 23 de diciembre de 1999 \u201cpor la cual se dictan normas en materia de vivienda, se se\u00f1alan los objetivos y criterios generales a los cuales debe sujetarse el Gobierno Nacional para regular un sistema especializado para su financiaci\u00f3n, se crean instrumentos de ahorro destinado a dicha financiaci\u00f3n, se dictan medidas relacionadas con los impuestos y otros costos vinculados a la construcci\u00f3n y negociaci\u00f3n de vivienda y se expiden otras disposiciones\u201d, estableci\u00f3 las normas y los criterios generales a los cuales debe circunscribirse el Gobierno Nacional para regular los sistemas de financiaci\u00f3n para la adquisici\u00f3n de vivienda individual a largo plazo, ligada al \u00edndice de precios al consumidor, y las condiciones especiales que regular\u00e1n la materia en punto de vivienda de inter\u00e9s social urbano y rural. En la misma disposici\u00f3n (par. 2) se se\u00f1al\u00f3 que las entidades podr\u00e1n otorgar cr\u00e9ditos de vivienda denominados en moneda legal colombiana o unidades de valor real (UVR), siempre que los sistemas de pago no contemplen capitalizaci\u00f3n de intereses, ni sanciones por prepagos totales o parciales\u201d. Cfr. T-701 de 2004. \u00a0<\/p>\n<p>7 Consejo de Estado, Sala de lo Contencioso Administrativo, Secci\u00f3n Quinta, exp. N\u00b0 08001-23-31-000-2002-0609-01. \u00a0<\/p>\n<p>8 Cfr. Cfr. . T-112\/03; T-535\/04; T-1243\/04. \u00a0<\/p>\n<p>9 Sobre la necesidad de cumplir los requisitos generales de aplicaci\u00f3n de la ley 546 de 1999 pueden consultarse las sentencias T-105\/05; T-1207\/04. \u00a0<\/p>\n<p>10 Informaci\u00f3n recogida de la Rese\u00f1a Esquem\u00e1tica T- 754002, elaborada por la Corte Constitucional el d\u00eda 10 de junio de 2003. \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia T-692\/05 \u00a0 ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Procedencia excepcional \u00a0 ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Requisitos generales y especiales de procedibilidad \u00a0 PROCESO EJECUTIVO HIPOTECARIO-Hip\u00f3tesis jurisprudenciales que dan lugar a la terminaci\u00f3n del proceso\/PROCESO EJECUTIVO HIPOTECARIO-Terminaci\u00f3n del proceso cuando a pesar de la reliquidaci\u00f3n quedan saldos insolutos pero las partes no llegan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63],"tags":[],"class_list":["post-12626","post","type-post","status-publish","format-standard","hentry","category-tutelas-2005"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/12626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=12626"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/12626\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=12626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=12626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=12626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}