{"id":12921,"date":"2024-06-04T15:49:36","date_gmt":"2024-06-04T15:49:36","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/06\/04\/c-180-06\/"},"modified":"2024-06-04T15:49:36","modified_gmt":"2024-06-04T15:49:36","slug":"c-180-06","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/c-180-06\/","title":{"rendered":"C-180-06"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia C-180\/06 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>INHIBICION DE LA CORTE CONSTITUCIONAL POR INEPTITUD SUSTANTIVA DE LA DEMANDA-Ausencia de cargos \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>RESERVA DE LEY ESTATUTARIA EN MATERIA DE JUSTICIA-No vulneraci\u00f3n al suprimir recurso extraordinario de s\u00faplica \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La norma demandada no regula la estructura de la administraci\u00f3n de justicia ni los principios generales para su funcionamiento y \u00a0s\u00f3lo suprime el recurso extraordinario de s\u00faplica previsto en el Art. 194 del C\u00f3digo Contencioso Administrativo, modificado por el Art. 57 de la Ley 446 de 1998, lo cual es materia propia de la ley ordinaria, conforme a lo dispuesto en el Art. 150, Num. 2, de la Constituci\u00f3n, en virtud del cual al Congreso de la Rep\u00fablica por medio de leyes corresponde expedir c\u00f3digos en todos los ramos de la legislaci\u00f3n y reformar sus disposiciones. En consecuencia, el cargo por violaci\u00f3n de la reserva de ley estatutaria no est\u00e1 llamado a prosperar. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>UNIFICACION DE JURISPRUDENCIA-Importancia\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Las decisiones de la Corte Constitucional en ejercicio del control abstracto de constitucionalidad consagrado en el Art. 241 superior producen efectos erga omnes, es decir, tienen car\u00e1cter vinculante u obligatorio para todas las personas, por la naturaleza y finalidad de dicho control, y, as\u00ed mismo, tienen el valor de cosa juzgada constitucional, de conformidad con lo dispuesto en el Art. 243 ib\u00eddem. Tales efectos en materia constitucional comprenden no s\u00f3lo la decisi\u00f3n misma contenida en la parte resolutiva de la sentencia, sino tambi\u00e9n las razones jur\u00eddicas contenidas en la parte motiva de esta \u00faltima que est\u00e9n relacionadas directa e indivisiblemente con aquella (ratio decidendi). \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>LIBERTAD DE CONFIGURACION LEGISLATIVA EN PROCEDIMIENTO JUDICIAL-Recursos y medios de defensa \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>RECURSO EXTRAORDINARIO DE SUPLICA EN PROCESO CONTENCIOSO ADMINISTRATIVO-Supresi\u00f3n no viola igualdad, acceso a la administraci\u00f3n de justicia, debido proceso, seguridad jur\u00eddica, confianza leg\u00edtima ni unidad del ordenamiento jur\u00eddico\/UNIFICACION DE JURISPRUDENCIA DEL CONSEJO DE ESTADO-No desaparece por la supresi\u00f3n del recurso extraordinario de s\u00faplica \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En el caso de la norma demandada el legislador suprimi\u00f3 el recurso extraordinario de s\u00faplica, que ten\u00eda la finalidad principal de unificar la jurisprudencia, por raz\u00f3n de la necesidad de descongestionar el funcionamiento de la jurisdicci\u00f3n de lo contencioso administrativo y, en particular, el de la Sala de lo Contencioso Administrativo del Consejo de Estado, que era la competente para conocer de dicho recurso, y con el prop\u00f3sito de asegurar el cumplimiento de los principios de celeridad y eficacia en la administraci\u00f3n de justicia en ese campo. La Sala debe se\u00f1alar que el mecanismo de unificaci\u00f3n de la jurisprudencia no desaparece con la decisi\u00f3n legislativa adoptada, ya que en adelante dicha funci\u00f3n deber\u00e1 ser cumplida por cada una de las secciones de la Sala de lo Contencioso Administrativo del Consejo de Estado, en el ejercicio de sus funciones propias, lo cual se justifica por su car\u00e1cter especializado de conformidad con el reglamento de dicha corporaci\u00f3n, y, por otra parte, que los motivos tenidos en cuenta por el legislador son constitucionalmente leg\u00edtimos y se ci\u00f1en a los criterios de razonabilidad y proporcionalidad. Igualmente, debe tenerse en cuenta que, a pesar de la medida adoptada, subsiste la posibilidad de que la Sala de lo Contencioso Administrativo del Consejo de Estado conozca de determinados asuntos y unifique por esa v\u00eda la jurisprudencia, de acuerdo con lo dispuesto en el Art. 130 del C. C. A., modificado por el Art. 38 de la Ley 446 de 1998, en virtud del cual \u201ca solicitud del Ministerio P\u00fablico, o de oficio, las Secciones podr\u00e1n remitir a la Sala Plena de lo Contencioso Administrativo aquellos asuntos que se encuentren para fallo y que por su importancia jur\u00eddica o trascendencia social ameriten ser decididos por \u00e9sta. La Sala Plena decidir\u00e1 si avoca o no el conocimiento del asunto. \u201cIgualmente, la Sala Plena podr\u00e1 asumir directamente el conocimiento de los asuntos que se encuentren para fallo en cualquiera de las Secciones.\u201d Por estas razones, la Corte concluye que la norma demandada no vulnera los derechos a la igualdad, el acceso a la administraci\u00f3n de justicia, el debido proceso y los principios de unidad del ordenamiento jur\u00eddico, seguridad jur\u00eddica y confianza leg\u00edtima. Por tanto, la declarar\u00e1 exequible, por los cargos analizados en esta sentencia. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Referencia: expediente D-5975 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Demanda de inconstitucionalidad contra los Arts. 2\u00ba y 3\u00ba de la Ley 954 de 2005 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Demandante: Andr\u00e9s Felipe Ram\u00edrez Gallego \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Magistrado Ponente:\u00a0 \u00a0<\/p>\n<p>Dr. JAIME ARAUJO RENTERIA \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Bogot\u00e1, D. C., \u00a0ocho ( 8 ) de marzo de dos mil seis (2006). \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La Sala Plena de la Corte Constitucional, en cumplimiento de sus atribuciones constitucionales y de los requisitos y tr\u00e1mite establecidos en el Decreto 2067 de 1991, ha proferido la siguiente \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>S E N T E N C I A\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>I. ANTECEDENTES \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En ejercicio de la acci\u00f3n p\u00fablica de inconstitucionalidad, el ciudadano Andr\u00e9s Felipe Ram\u00edrez Gallego present\u00f3 demanda contra los Arts. 2\u00ba y 3\u00ba de la Ley 954 de 2005, por medio de la cual se modifican, adicionan y derogan algunos art\u00edculos de la Ley 446 de 1998 y del C\u00f3digo Contencioso Administrativo, y se dictan otras disposiciones sobre competencia, descongesti\u00f3n, eficiencia y acceso a la administraci\u00f3n de justicia. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Cumplidos los tr\u00e1mites constitucionales y legales propios de los procesos de inconstitucionalidad, la Corte Constitucional procede a decidir acerca de la demanda de la referencia. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>II. NORMAS \u00a0DEMANDADAS \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>A continuaci\u00f3n se transcriben las disposiciones demandadas, conforme a su publicaci\u00f3n en el Diario Oficial No. 45.893 de 28 de abril de 2005: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ART\u00cdCULO 2o. RECURSO EXTRAORDINARIO DE S\u00daPLICA. Der\u00f3gase el art\u00edculo 194, modificado por el art\u00edculo 57 de la Ley 446 de 1998, del C\u00f3digo Contencioso Administrativo. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>ART\u00cdCULO 3o. SALAS ESPECIALES TRANSITORIAS DE DECISI\u00d3N. Adici\u00f3nase un art\u00edculo nuevo transitorio en la Secci\u00f3n Segunda, del Cap\u00edtulo Tercero, del T\u00edtulo XXXIII, del Libro Cuarto del C\u00f3digo Contencioso Administrativo, referente al recurso de s\u00faplica, el cual quedar\u00e1 as\u00ed: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0Art\u00edculo transitorio. Salas Especiales Transitorias de Decisi\u00f3n. Cr\u00e9anse en el Consejo de Estado Salas Especiales Transitorias de Decisi\u00f3n, encargadas de decidir los recursos extraordinarios de s\u00faplica que, a la fecha de entrada en vigencia de la presente ley, tengan proferido el respectivo auto admisorio. Estas Salas estar\u00e1n conformadas por cuatro Magistrados de la Sala Contencioso Administrativa del Consejo de Estado, pertenecientes a cada una de las Secciones que integran dicha Sala, con excepci\u00f3n de la Secci\u00f3n que profiri\u00f3 la providencia impugnada. Su integraci\u00f3n y funcionamiento se har\u00e1 de conformidad con lo que al respecto establezca el Reglamento que para tal efecto expida el Consejo, y el fallo se adoptar\u00e1 dentro de los t\u00e9rminos previstos en el mismo. \u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>En caso de presentarse empate en las Salas Especiales, se sortear\u00e1 un Magistrado adicional entre los restantes Magistrados de la Sala Contencioso Administrativa con el fin de que lo dirima, excluyendo a aquellos integrantes de la Secci\u00f3n que produjo la providencia recurrida. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>La vigencia de cada una de las Salas Especiales de Decisi\u00f3n culminar\u00e1 una vez fallados todos los asuntos a ellas entregados en el respectivo reparto. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>III. DEMANDA \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El demandante considera violados el pre\u00e1mbulo y los Arts. 1, 2, 3, 4, 6, 13, 29, 31, 40, 83,85,86, 93, 94, 95, 103, 113, 114, 116, 150, 152, 236, 237, 238, 241.4, 242 y 243 de la Constituci\u00f3n Pol\u00edtica, con los siguientes fundamentos: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Afirma que las normas demandadas, al eliminar el recurso extraordinario de s\u00faplica en la jurisdicci\u00f3n contenciosa administrativa, como medio de unificaci\u00f3n de la jurisprudencia, vulneran el principio de igualdad, porque se dan casos en que las secciones de la Sala Contencioso Administrativa del Consejo de Estado tienen jurisprudencias dispares sobre los temas jur\u00eddicos y seg\u00fan la Constituci\u00f3n la aplicaci\u00f3n del Derecho debe ser igual para todas las personas. Agrega que dichas disposiciones no respetan la unidad del ordenamiento jur\u00eddico, sobre la base del contenido de la Constituci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Expresa que se viola el derecho a la administraci\u00f3n de justicia porque los jueces pueden negarlo por v\u00eda de interpretaci\u00f3n de las normas jur\u00eddicas y sin un debido control de los superiores. A\u00f1ade que al privar a las personas del recurso extraordinario y de la posibilidad de controvertir las sentencias mediante el mismo, se viola el debido proceso, as\u00ed como tambi\u00e9n el principio de la confianza leg\u00edtima en la adopci\u00f3n de decisiones por parte de las autoridades p\u00fablicas, en cuanto la respuesta de \u00e9stas debe ser la misma en situaciones iguales. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sostiene que se quebranta el principio de seguridad jur\u00eddica, ya que no puede existir \u00e9sta en un Estado donde cada d\u00eda se profieran sentencias dis\u00edmiles sobre un mismo punto de Derecho y que una decisi\u00f3n que ha sido adoptada una vez no puede abandonarse sin un motivo para ello. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Manifiesta que la eliminaci\u00f3n del recurso extraordinario origina el uso alternativo de la acci\u00f3n de tutela para lograr la protecci\u00f3n del derecho a la igualdad ante la ley y que as\u00ed la unificaci\u00f3n jurisprudencial no ser\u00eda dada por el juez natural. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Aduce que por afectar el recurso extraordinario de s\u00faplica los derechos fundamentales a la igualdad, el debido proceso y el acceso a la administraci\u00f3n de justicia, y modificar las competencias de la Ley 270 de 1996, Estatutaria de la Administraci\u00f3n de Justicia, el Congreso transgredi\u00f3 el principio de reserva de ley estatutaria previsto en los Arts. 152 y 153 de la Constituci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Indica que \u201ces importante se\u00f1alar que lo que se busca con el recurso como muchos pudieran pensar es un manejo racional del principio de seguridad jur\u00eddica, no para que la jurisprudencia quede est\u00e1tica, sino simplemente para que el administrado tenga reglas claras, precisas, previas y relativamente estables de interpretaci\u00f3n. Es mantener una interpretaci\u00f3n hasta que el pleno del consejo mediante un procedimiento un poco m\u00e1s complejo la cambie o que las secciones haciendo un uso adecuado del precedente, distingan su caso del anterior o modifiquen la jurisprudencia (\u2026)\u201d. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Concluye que no se pueden derogar ni expresa ni t\u00e1citamente los recursos de unificaci\u00f3n de las varias jurisdicciones, porque es dejar sin contenido una competencia se\u00f1alada por la Constituci\u00f3n a los altos tribunales. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>IV. INTERVENCIONES \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1. Intervenci\u00f3n del Ministerio del Interior y de Justicia \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Mediante escrito presentado el 12 de Octubre de 2005, el ciudadano Fernando G\u00f3mez Mej\u00eda, obrando en nombre del Ministerio del Interior y de Justicia, solicita a la Corte que declare exequibles las normas demandadas, argumentando lo siguiente: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Expone que con fundamento en la cl\u00e1usula de competencia general del Congreso de la Rep\u00fablica para la expedici\u00f3n de las leyes, consagrada en el Art. 150 de la Constituci\u00f3n, en concordancia con lo dispuesto en los Arts. 29 y 228 ib\u00eddem, espec\u00edficamente con base en lo previsto en el Num. 2 del primer art\u00edculo, en virtud del cual corresponde a aquella corporaci\u00f3n expedir c\u00f3digos en todos los ramos de la legislaci\u00f3n y reformar sus disposiciones, la Corte Constitucional ha expresado numerosas veces que el legislador tiene libertad de configuraci\u00f3n para crear y modificar los procesos y actuaciones judiciales, en sus diversos aspectos, siempre y cuando respete los derechos, garant\u00edas, principios y valores contemplados en la misma Constituci\u00f3n y obre conforme a los principios de razonabilidad y proporcionalidad. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Asevera que nuestro pa\u00eds es heredero de la tradici\u00f3n jur\u00eddica latina en cuanto al papel atribuido a la jurisprudencia como fuente del Derecho, seg\u00fan la cual la ley escrita es la principal fuente de Derecho y la jurisprudencia ocupa un lugar secundario, diferente del sistema anglosaj\u00f3n, en el cual la jurisprudencia es la fuente principal de Derecho, de tal manera que los jueces al momento de dictar sentencia consultan los antecedentes que existan en el conjunto de sentencias precedentes y la ley escrita ocupa un lugar secundario. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Enuncia que por ello en Colombia la jurisprudencia administrativa tiene en principio una fuerza jur\u00eddica secundaria, pues ella orienta, auxilia, ayuda y apoya la decisi\u00f3n del juez, que se basa esencialmente en la ley y en ning\u00fan momento ella sola puede servir de fundamento principal o exclusivo para justificar una decisi\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Se\u00f1ala que, por disposici\u00f3n de la Constituci\u00f3n, la jurisprudencia constitucional y el resto de la jurisprudencia del pa\u00eds tienen diferente fuerza jur\u00eddica. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Concluye que las normas impugnadas no vulneran los principios de igualdad, acceso a la administraci\u00f3n de justicia y debido proceso. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2. Intervenci\u00f3n de la Facultad de Derecho de la Universidad Santiago de Cali \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por medio de escrito recibido del 11 de Octubre de 2005, la ciudadana Beatriz Delgado Motoa, actuando en representaci\u00f3n de la Facultad de Derecho de la Universidad Santiago de Cali, coadyuva la petici\u00f3n del demandante, con las siguientes razones: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Se\u00f1ala en forma general la historia del recurso extraordinario de s\u00faplica en la jurisdicci\u00f3n contenciosa administrativa dentro del ordenamiento jur\u00eddico colombiano y afirma que el mismo tiene no s\u00f3lo la finalidad de la salvaguarda del orden jur\u00eddico sino tambi\u00e9n la de unificar la jurisprudencia, tal como sucede \u00a0con el recurso de casaci\u00f3n en la jurisdicci\u00f3n ordinaria. Agrega que tradicionalmente se ha sostenido que a trav\u00e9s de dicho recurso se busca que las secciones no terminen manejando la jurisprudencia, cada una por su lado, como si se tratara de otros tantos Consejos de Estado. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Arguye que, no obstante, el legislador colombiano estim\u00f3, en ejercicio de su discrecionalidad pol\u00edtica y de configuraci\u00f3n legislativa, que esta finalidad es sacrificable en aras de promover la descongesti\u00f3n de los despachos judiciales y, en especial, la de la Sala Plena del Consejo de Estado, sin estimar que ello se traduzca en una denegaci\u00f3n de justicia ni en ruptura alguna del sistema constitucional vigente. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Considera que las normas demandadas deben ser declaradas inexequibles porque la decisi\u00f3n de suprimir el recurso extraordinario de s\u00faplica en aras de la descongesti\u00f3n de la Sala Plena del Consejo de Estado y en desmedro de la posibilidad real de impugnar decisiones judiciales violatorias de normas sustanciales va en contrav\u00eda de valores m\u00e1s caros como son la justicia real y la igualdad efectiva, que son inseparables del Estado Social de Derecho. La medida resulta, pues, desproporcionada y, por ende, inconstitucional. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sostiene que el af\u00e1n de descongesti\u00f3n en la jurisdicci\u00f3n no se logra sino aparentemente, porque lo \u00fanico que conseguir\u00e1 es reforzar la sobrecarga de acciones de tutela que en adelante intentar\u00e1n los litigantes contra las sentencias de las secciones y las subsecciones ante la ausencia del citado recurso.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>3. Intervenciones extempor\u00e1neas \u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>En forma extempor\u00e1nea \u00a0se recibieron los siguientes escritos de intervenci\u00f3n, \u00a0los cuales, por tal motivo, no ser\u00e1n tenidos en cuenta: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>&#8211; El 19 de Octubre de 2005, escrito presentado por el ciudadano Germ\u00e1n Rodr\u00edguez Villamizar, obrando en nombre del Consejo de Estado. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>&#8211; El 24 de Octubre de 2005, escrito firmado por el ciudadano Edgardo Jos\u00e9 Maestre S\u00e1nchez, actuando en representaci\u00f3n de la Facultad de Derecho, Ciencias Pol\u00edticas y Sociales de la Universidad Popular del Cesar.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>V. CONCEPTO DEL PROCURADOR GENERAL DE LA NACION \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Mediante Concepto No. 3985 rendido el 8 de Noviembre de 2005, el Procurador General de la Naci\u00f3n (E), Carlos Arturo G\u00f3mez Pavajeau, solicita a la Corte que: i) se declare inhibida para hacer pronunciamiento de fondo en relaci\u00f3n con la supuesta violaci\u00f3n de las normas constitucionales en que incurri\u00f3 el legislador con la expedici\u00f3n del Art. 3\u00ba de la Ley 954 de 2005, por ineptitud sustantiva de la demanda; ii) estarse a lo que se disponga en las sentencias que se profieran dentro del tr\u00e1mite de los expedientes D-5822 y D-5965 que cursan en la Corte Constitucional frente a los cargos formulados contra el Art. 2\u00ba de la Ley 954 de 2005. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Subsidiariamente pide a la Corte que: i) declare exequible el Art. 2\u00ba de la Ley 954 de 2005; ii) declare inexequible la expresi\u00f3n \u201cque, a la fecha de entrada en vigencia de la presente ley, tengan proferido el respectivo auto admisorio\u201d, contenida en el Art. 3\u00ba de la Ley 954 de 2005. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sustenta sus peticiones en los siguientes argumentos: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Plantea que, a pesar del esfuerzo del demandante para demostrar los cargos, no existe una acusaci\u00f3n concreta contra el Art. 3\u00ba de la Ley 954 de 2005 que crea las Salas Especiales Transitorias de Decisi\u00f3n y les asigna funciones en relaci\u00f3n con el recurso extraordinario de s\u00faplica, excluyendo de tal competencia los recursos presentados y a\u00fan no admitidos, raz\u00f3n por la cual, con \u00a0fundamento en la jurisprudencia de la Corte Constitucional se impone, en relaci\u00f3n con dicha norma, una decisi\u00f3n inhibitoria. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Alega que, igualmente, la demanda presentada, aunque con sustento distinto de los cargos, es en esencia igual a las que dieron lugar a los conceptos emitidos por la Procuradur\u00eda General de la Naci\u00f3n dentro del tr\u00e1mite de los expedientes radicados bajo los Nos. D-5822 D-5965 y persigue un mismo objeto, por lo cual en esta oportunidad se reitera, en lo pertinente, la posici\u00f3n del Ministerio P\u00fablico, con las modificaciones y adiciones propias del cargo referido al logro de la seguridad jur\u00eddica a trav\u00e9s de unificaci\u00f3n jurisprudencial en la jurisdicci\u00f3n contenciosa administrativa. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Dictamina que en materia de recursos la Corte Constitucional ha dicho que, salvo las limitaciones impuestas en materia penal cuando existe sentencia condenatoria y en materia de tutela, el legislador puede establecer los recursos que proceden en cada jurisdicci\u00f3n. As\u00ed, como la Constituci\u00f3n no establece la obligatoriedad de un recurso determinado ante la jurisdicci\u00f3n contenciosa administrativa, se ampl\u00eda para el legislador el margen de libertad configurativa de las normas que los consagran, siendo permitida su inclusi\u00f3n o exclusi\u00f3n en el ordenamiento jur\u00eddico bajo el criterio de razonabilidad. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Indica que la Ley 954 de 2005 tiene como finalidad la descongesti\u00f3n de despachos judiciales y que la supresi\u00f3n del recurso extraordinario de s\u00faplica es una medida razonable y proporcional al fin perseguido por el legislador. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Afirma que para las personas que hab\u00edan presentado oportunamente el recurso extraordinario de s\u00faplica bajo la vigencia del Art. 194 del C\u00f3digo Contencioso \u00a0Administrativo y la decisi\u00f3n sobre su admisi\u00f3n no se hab\u00eda producido al comenzar la vigencia de la citada ley, resulta v\u00e1lida, desde el punto de vista de la doctrina constitucional, la garant\u00eda de la expectativa cierta, de conformidad con el principio de la confianza leg\u00edtima, de suerte que deb\u00eda ordenarse la tramitaci\u00f3n y resoluci\u00f3n del recurso interpuesto, lo cual neg\u00f3 el legislador. En consecuencia, existe violaci\u00f3n del derecho al debido proceso y de dicho principio. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Enuncia que no es estatutaria la ley utilizada por el legislador para expedir el C\u00f3digo Contencioso Administrativo, ni las leyes que lo modifican, entre otras la Ley 446 de 1998 y la que se cuestiona en esta oportunidad, pues no se afecta la estructura de la administraci\u00f3n de justicia ni los principios sustanciales y procedimentales aplicables en la actividad de los jueces. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sostiene que si bien los recursos extraordinarios contribuyen a la unificaci\u00f3n de la jurisprudencia en la jurisdicci\u00f3n de lo contencioso administrativo, el de s\u00faplica no es el \u00fanico instrumento con que se cuenta para ese fin, ya que en virtud de lo dispuesto por el Art. 130 del C. C. A. la Sala Plena de lo Contencioso Administrativo del Consejo de Estado asume los asuntos que por su importancia jur\u00eddica o su trascendencia social le sean enviados por las secciones y, de igual manera, puede asumir cualquier asunto que se encuentre \u00a0para fallo en cualquiera de las secciones de dicha corporaci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>VI. CONSIDERACIONES Y FUNDAMENTOS DE LA CORTE \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Competencia \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1. La Corte Constitucional es competente para conocer de \u00a0la presente demanda, conforme a lo dispuesto en el art\u00edculo 241, Num. 4, de la Constituci\u00f3n, por estar dirigida contra unas disposiciones que forman parte de una \u00a0ley. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Consideraci\u00f3n preliminar. Declaraci\u00f3n de inhibici\u00f3n en relaci\u00f3n con la demanda contra el Art. 3\u00ba de la Ley 954 de 2005, por ineptitud sustantiva de la demanda \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2. Como lo afirma el se\u00f1or Procurador General de la Naci\u00f3n (E) en su concepto, en la demanda no se formulan cargos de inconstitucionalidad contra el Art. 3\u00ba de la Ley 954 de 2005, en virtud del cual se crearon en el Consejo de Estado unas Salas Especiales Transitorias de Decisi\u00f3n, encargadas de decidir los recursos extraordinarios de s\u00faplica que, a la fecha de entrada en vigencia de la misma ley, tuvieran proferido el respectivo auto admisorio, y se se\u00f1alaron su integraci\u00f3n, funcionamiento y vigencia. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por esta raz\u00f3n, con fundamento en lo dispuesto en el Art. 2\u00ba del Decreto 2067 de 1991, que se\u00f1ala los requisitos de las demandas de inconstitucionalidad, y en la jurisprudencia reiterada de la Corte Constitucional, esta corporaci\u00f3n se declarar\u00e1 inhibida para proferir decisi\u00f3n de m\u00e9rito respecto de la demanda contra dicha disposici\u00f3n, por ineptitud sustantiva de la demanda. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Problema jur\u00eddico planteado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>3. \u00a0Corresponde a la Corte establecer si el Art. 2\u00ba de la Ley 954 de 2005, al suprimir el recurso extraordinario de s\u00faplica en la jurisdicci\u00f3n de lo contencioso administrativo, como medio de unificaci\u00f3n de la jurisprudencia: \u00a0i) quebrant\u00f3 la reserva de ley estatutaria (Art. 152 C. Pol.); ii) vulner\u00f3 los derechos a la igualdad, el acceso a la administraci\u00f3n de justicia, el debido proceso y los principios de unidad del ordenamiento jur\u00eddico, seguridad jur\u00eddica y confianza leg\u00edtima. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Examen de los cargos formulados \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La supresi\u00f3n del recurso extraordinario de s\u00faplica en la jurisdicci\u00f3n de lo contencioso administrativo no es materia de reserva de ley estatutaria \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>4. De conformidad con lo dispuesto en el Art. 152 de la Constituci\u00f3n, mediante las leyes estatutarias el Congreso de la Rep\u00fablica regular\u00e1, entre otras materias, la administraci\u00f3n de justicia (Lit. b). \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La Corte Constitucional ha examinado en repetidas ocasiones este tema y ha se\u00f1alado que esta disposici\u00f3n superior no entra\u00f1a que todos los temas relativos a la administraci\u00f3n de justicia deban regularse mediante leyes estatutarias y ha precisado que \u00fanicamente la estructura de aquella y los principios generales sobre su funcionamiento requieren la expedici\u00f3n de las mismas.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sobre el particular, al estudiar la constitucionalidad de la Ley 270 de 1996, Estatutaria de la Administraci\u00f3n de Justicia, expres\u00f3: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201c(\u2026) para la Corte, una ley estatutaria encargada de regular la administraci\u00f3n de justicia, como lo dispone el literal b) del art\u00edculo 152 superior, debe ocuparse esencialmente sobre la estructura general de la administraci\u00f3n de justicia y sobre los principios sustanciales y procesales que deben guiar a los jueces en su funci\u00f3n de dirimir los diferentes conflictos o asuntos que se someten a su conocimiento. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cDe conformidad con lo anterior, esta Corporaci\u00f3n entiende que el legislador goza, en principio, de la autonom\u00eda suficiente para definir cu\u00e1les aspectos del derecho deben hacer parte de este tipo de leyes. Sin embargo, debe se\u00f1alarse que esa habilitaci\u00f3n no incluye la facultad de consagrar asuntos o materias propias de los c\u00f3digos de procedimiento, responsabilidad esta que se debe asumir con base en lo dispuesto en el numeral 2o del art\u00edculo 150 superior, es decir, a trav\u00e9s de las leyes ordinarias. Con todo, debe reconocerse que no es asunto sencillo establecer una diferenciaci\u00f3n clara y contundente respecto de las materias que deben ocuparse uno y otro tipo de leyes. As\u00ed, pues, resulta claro que, al igual que ocurre para el caso de las leyes estatutarias que regulan los derechos fundamentales (literal A del art\u00edculo 152), no todo aspecto que de una forma u otra se relacione con la administraci\u00f3n de justicia debe necesariamente hacer parte de una ley estatutaria. De ser ello as\u00ed, entonces resultar\u00eda nugatoria la atribuci\u00f3n del numeral 2o del art\u00edculo 150 y, en consecuencia, cualquier c\u00f3digo que en la actualidad regule el ordenamiento jur\u00eddico, o cualquier modificaci\u00f3n que en la materia se realice, deber\u00e1 someterse al tr\u00e1mite previsto en el art\u00edculo 153 de la Carta.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cLo expuesto no significa que, de manera autom\u00e1tica, cualquier asunto que se incluya en el presente proyecto de ley que de una forma u otra se relacione con procedimientos legales deba retirarse del ordenamiento jur\u00eddico. Esa decisi\u00f3n depender\u00e1 del an\u00e1lisis de cada caso en particular, esto es, de una labor de concretizaci\u00f3n que adelantar\u00e1 la Corte para definir, a la luz de la Constituci\u00f3n, si en cada uno de los eventos que se analicen se amerita o no que la ley estatutaria se ocupe de regular aspectos que, en primera instancia, son de naturaleza procesal. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cLas consideraciones precedentes sirven, adem\u00e1s, de fundamento para advertir la inconveniencia de permitir al legislador regular aspectos propios de ley procesal en una ley estatutaria, pues es sabido que el tr\u00e1mite de este tipo de normatividad reviste caracter\u00edsticas especiales -aprobaci\u00f3n en una sola legislatura, votaci\u00f3n mayoritaria de los miembros del Congreso, revisi\u00f3n previa de la Corte Constitucional-, las cuales naturalmente no se compatibilizan con la facultad que le asiste al legislador para expedir o modificar c\u00f3digos \u00a0a trav\u00e9s de mecanismos eficaces -es decir, mediante el tr\u00e1mite ordinario-, en los eventos en que las necesidades del pa\u00eds as\u00ed lo ameriten. Permitir lo contrario ser\u00eda tanto como admitir la petrificaci\u00f3n de las normas procesales y la consecuente imposibilidad de contar con una administraci\u00f3n de justicia seria, responsable, eficaz y diligente.\u201d1 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>Se observa que la norma demandada no regula la estructura de la administraci\u00f3n de justicia ni los principios generales para su funcionamiento y \u00a0s\u00f3lo suprime el recurso extraordinario de s\u00faplica previsto en el Art. 194 del C\u00f3digo Contencioso Administrativo, modificado por el Art. 57 de la Ley 446 de 1998, lo cual es materia propia de la ley ordinaria, conforme a lo dispuesto en el Art. 150, Num. 2, de la Constituci\u00f3n, en virtud del cual al Congreso de la Rep\u00fablica por medio de leyes corresponde expedir c\u00f3digos en todos los ramos de la legislaci\u00f3n y reformar sus disposiciones. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En consecuencia, el cargo por violaci\u00f3n de la reserva de ley estatutaria no est\u00e1 llamado a prosperar. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La supresi\u00f3n del recurso extraordinario de s\u00faplica en la jurisdicci\u00f3n de lo contencioso administrativo no vulnera los derechos y principios se\u00f1alados en la demanda \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>5. El actor considera que el Art. 2\u00ba de la Ley 954 de 2005, al derogar expresamente el Art. 194 del C. C. A., modificado por el Art. 57 de la Ley 446 de 1998, que consagraba el recurso extraordinario de s\u00faplica en la jurisdicci\u00f3n de lo contencioso administrativo como medio de unificaci\u00f3n de la jurisprudencia, vulner\u00f3 los derechos a la igualdad, el acceso a la administraci\u00f3n de justicia, el debido proceso y los principios de unidad del ordenamiento jur\u00eddico, seguridad jur\u00eddica y confianza leg\u00edtima. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>6. La disposici\u00f3n derogada regulaba el citado recurso en los siguientes t\u00e9rminos: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ARTICULO 194. DEL RECURSO EXTRAORDINARIO DE SUPLICA. El recurso extraordinario de s\u00faplica, procede contra las sentencias ejecutoriadas dictadas por cualquiera de las Secciones o Subsecciones del Consejo de Estado. Es causal del recurso extraordinario de s\u00faplica la violaci\u00f3n directa de normas sustanciales, ya sea por aplicaci\u00f3n indebida, falta de aplicaci\u00f3n o interpretaci\u00f3n err\u00f3nea de las mismas. Los miembros de la Secci\u00f3n o Subsecci\u00f3n falladora estar\u00e1n excluidos de la decisi\u00f3n, pero podr\u00e1n ser o\u00eddos si la Sala as\u00ed lo determina.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En el escrito que contenga el recurso se indicar\u00e1 en forma precisa la norma o normas sustanciales infringidas y los motivos de la infracci\u00f3n; y deber\u00e1 interponerse dentro de los veinte (20) d\u00edas siguientes al de la ejecutoria de la sentencia impugnada, ante la Secci\u00f3n o Subsecci\u00f3n falladora que lo conceder\u00e1 o rechazar\u00e1.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Admitido el recurso por el ponente en Sala Plena, se ordenar\u00e1 el traslado a las dem\u00e1s partes para alegar por el t\u00e9rmino com\u00fan de diez (10) d\u00edas. Vencido el t\u00e9rmino de traslado, dentro de los treinta (30) d\u00edas siguientes se registrar\u00e1 el proyecto de fallo. Si la Sala hallare procedente la causal invocada, infirmar\u00e1 la sentencia recurrida y dictar\u00e1 la que deba reemplazarla. Si la sentencia recurrida tuvo cumplimiento, declarar\u00e1 sin efectos los actos procesales realizados con tal fin y dispondr\u00e1 que el Juez de conocimiento proceda a las restituciones y adopte las dem\u00e1s medidas a que hubiere lugar.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Si el recurso es desestimado, la parte recurrente ser\u00e1 condenada en costas, para lo cual se aplicar\u00e1n las normas previstas en el C\u00f3digo de Procedimiento Civil.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La interposici\u00f3n de este recurso no impide la ejecuci\u00f3n de la sentencia. Con todo, cuando se trate de sentencia condenatoria de contenido econ\u00f3mico, el recurrente podr\u00e1 solicitar que se suspenda el cumplimiento de la misma, prestando cauci\u00f3n para responder por los perjuicios que dicha suspensi\u00f3n cause a la parte contraria, incluyendo los frutos civiles y naturales que puedan percibirse durante aquella. El ponente fijar\u00e1 el monto, naturaleza y t\u00e9rmino para constituir la cauci\u00f3n, cuyo incumplimiento por parte del recurrente implica que se declare desierto el recurso. Los efectos de la sentencia quedan suspendidos hasta cuando se decida.&#8221;\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Se \u00a0nota que la causal \u00fanica de este recurso era parcialmente igual a una de las causales de casaci\u00f3n, que consiste en ser la sentencia violatoria de una norma de derecho sustancial, directa o indirectamente, esto \u00faltimo por errores (de hecho o de derecho) en la apreciaci\u00f3n de las pruebas de los hechos (Art. 368 C. P. C., modificado por el Art. 1\u00ba , Num. 183, \u00a0del Decreto ley 2282 de 1989; Art. 87 del C. P. T., modificado por el Art. 60 del Decreto 528 de 1964; Art. 207 Ley 600 de 2000).\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Es oportuno se\u00f1alar que, conforme a lo previsto en el Art.365 del C. P. C., el recurso de casaci\u00f3n tiene por fin primordial unificar la jurisprudencia nacional y proveer a la realizaci\u00f3n del derecho objetivo en los respectivos procesos; adem\u00e1s procura reparar los agravios inferidos a las partes por la sentencia recurrida. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7. Seg\u00fan lo dispuesto en el Art. 230 de la Constituci\u00f3n, \u201clos jueces, en sus providencias, s\u00f3lo est\u00e1n sometidos al imperio de la ley.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cLa equidad, la jurisprudencia, los principios generales del derecho y la doctrina son criterios auxiliares de la actividad judicial\u201d. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Cabe se\u00f1alar que las decisiones de la Corte Constitucional en ejercicio del control abstracto de constitucionalidad consagrado en el Art. 241 superior producen efectos erga omnes, es decir, tienen car\u00e1cter vinculante u obligatorio para todas las personas, por la naturaleza y finalidad de dicho control, y, as\u00ed mismo, tienen el valor de cosa juzgada constitucional, de conformidad con lo dispuesto en el Art. 243 ib\u00eddem. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Tales efectos en materia constitucional comprenden no s\u00f3lo la decisi\u00f3n misma contenida en la parte resolutiva de la sentencia, sino tambi\u00e9n las razones jur\u00eddicas contenidas en la parte motiva de esta \u00faltima que est\u00e9n relacionadas directa e indivisiblemente con aquella (ratio decidendi). A este respecto la Corte Constitucional ha se\u00f1alado:\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201c3. \u00bfQue parte de las sentencias de constitucionalidad tiene la fuerza de la cosa juzgada? \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cLa respuesta es doble: poseen tal car\u00e1cter algunos apartes de las sentencias en forma expl\u00edcita y otros en forma impl\u00edcita. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cPrimero, goza de cosa juzgada expl\u00edcita la parte resolutiva de las sentencias, por expresa disposici\u00f3n del art\u00edculo 243 de la Constituci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cSegundo, gozan de cosa juzgada impl\u00edcita los conceptos de la parte motiva que guarden una unidad de sentido con el dispositivo de la sentencia, de tal forma que no se pueda entender \u00e9ste sin la alusi\u00f3n a aqu\u00e9llos. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cEn efecto, la parte motiva de una sentencia de constitucionalidad tiene en principio el valor que la Constituci\u00f3n le asigna a la doctrina en el inciso segundo del art\u00edculo 230: criterio auxiliar -no obligatorio-, esto es, ella se considera obiter dicta. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cDistinta suerte corren los fundamentos contenidos en las sentencias de la Corte Constitucional que guarden relaci\u00f3n directa con la parte resolutiva, as\u00ed como los que la Corporaci\u00f3n misma indique, pues tales argumentos, en la medida en que tengan un nexo causal con la parte resolutiva, son tambi\u00e9n obligatorios y, en esas condiciones, deben ser observados por las autoridades y corrigen la jurisprudencia\u201d.2\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>8. Esta corporaci\u00f3n ha manifestado numerosas veces que con fundamento en lo previsto en los Arts. 29, 114, 150 y 228 de la Constituci\u00f3n el legislador tiene una libertad de configuraci\u00f3n amplia en materia de procedimientos judiciales, siempre y cuando respete los valores y principios constitucionales y los derechos y garant\u00edas fundamentales y obre tambi\u00e9n con un criterio de razonabilidad y proporcionalidad. En este sentido ha indicado: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>\u201cConforme lo ha sostenido la Corte en reiterada jurisprudencia3, en virtud de la cl\u00e1usula gen|eral de competencia contemplada en los numerales 1\u00b0 y 2\u00b0 del art\u00edculo 150 de la Constituci\u00f3n, corresponde al legislador configurar la totalidad de los procedimientos y reg\u00edmenes aplicables en las actuaciones judiciales y administrativas. Para el ejercicio de dicha competencia goza de un amplio margen de autonom\u00eda y libertad de configuraci\u00f3n pol\u00edtica que lo legitima para evaluar y definir con independencia \u00a0las etapas, caracter\u00edsticas, formas, plazos, t\u00e9rminos, y en general lo relativo a las condiciones de acceso, tr\u00e1mite y conclusi\u00f3n de esas actuaciones4. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cParalelamente, tambi\u00e9n ha enfatizado la Corte que tal autonom\u00eda legislativa, pese a su amplitud y flexibilidad, no puede tornarse en absoluta; ella se encuentra condicionada por precisos l\u00edmites. As\u00ed, en materia de configuraci\u00f3n \u00a0del sistema judicial, esos l\u00edmites se materializan en los criterios de razonabilidad y proporcionalidad que deben asistir esas regulaciones, de forma tal que con ellas se permita un ejercicio \u00fatil de las garant\u00edas y principios \u00a0constitucionales, para el aseguramiento efectivo de los derechos consagrados en la Constituci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cA\u00fan la introducci\u00f3n de ciertas restricciones, o tratamientos diferenciados encuentran el aval constitucional cuando resultan razonables, o persiguen un fin \u00a0auspiciado por la propia Carta, y cuando adem\u00e1s las medidas adoptadas resultan proporcionadas a ese fin constitucionalmente l\u00edcito\u201d.5 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En otra ocasi\u00f3n expuso: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cEn desarrollo de esta competencia, el legislador est\u00e1 habilitado para regular los siguientes aspectos: \u00a0<\/p>\n<p>\u201cEl legislador goza de libertad de configuraci\u00f3n en lo referente al establecimiento de los recursos y medios de defensa que pueden intentar los administrados contra los actos que profieren las autoridades. Es la ley, no la Constituci\u00f3n, la que se\u00f1ala si determinado recurso -reposici\u00f3n, apelaci\u00f3n, u otro- tiene o no cabida respecto de cierta decisi\u00f3n, y es la ley, por tanto, la encargada de dise\u00f1ar en todos sus pormenores las reglas dentro de las cuales tal recurso puede ser interpuesto, ante qui\u00e9n, en qu\u00e9 oportunidad, cu\u00e1ndo no es procedente y cu\u00e1les son los requisitos -positivos y negativos- que deben darse para su ejercicio. 6 \u00a0<\/p>\n<p>\u201cCorresponde al Congreso fijar las etapas de los diferentes procesos y establecer los t\u00e9rminos y las formalidades que deben cumplir. Sin embargo, en esta labor el legislador tiene ciertos l\u00edmites, representados fundamentalmente en su obligaci\u00f3n de atender los principios y fines del Estado y de velar por la vigencia de los derechos fundamentales de los ciudadanos.7\u201d 8 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>9. La unificaci\u00f3n de la jurisprudencia por parte de los altos tribunales tiene un papel muy importante en la interpretaci\u00f3n y la aplicaci\u00f3n de las disposiciones jur\u00eddicas por parte de los jueces, en cuanto garantiza los principios de seguridad jur\u00eddica y de igualdad de las personas.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Con el fin de lograr tales objetivos, en ejercicio de la mencionada libertad de configuraci\u00f3n normativa, el legislador puede establecer mecanismos procesales de unificaci\u00f3n de la jurisprudencia, mediante recursos o tr\u00e1mites especiales ante las altas corporaciones judiciales, y, as\u00ed mismo, puede modificar o suprimir los existentes, con los l\u00edmites superiores indicados. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En el caso de la norma demandada el legislador suprimi\u00f3 el recurso extraordinario de s\u00faplica, que ten\u00eda la finalidad principal de unificar la jurisprudencia, por raz\u00f3n de la necesidad de descongestionar el funcionamiento de la jurisdicci\u00f3n de lo contencioso administrativo y, en particular, el de la Sala de lo Contencioso Administrativo del Consejo de Estado, que era la competente para conocer de dicho recurso, y con el prop\u00f3sito de asegurar el cumplimiento de los principios de celeridad y eficacia en la administraci\u00f3n de justicia en ese campo. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Dichos motivos fueron expresados en la exposici\u00f3n correspondiente, en el tr\u00e1mite de formaci\u00f3n de la ley, en los siguientes t\u00e9rminos:\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cEl proyecto de ley que se presenta a la consideraci\u00f3n del honorable Congreso de la Rep\u00fablica tiene el prop\u00f3sito fundamental de descongestionar tanto la Sala Plena de lo Contencioso Administrativo, como las diferentes Secciones que la integran, todas las cuales viven una verdadera situaci\u00f3n de emergencia, pues las medidas establecidas en la Ley 446 de 1998 y, en especial, la creaci\u00f3n de los juzgados administrativos, no han podido ponerse en funcionamiento por falta de recursos presupuestales suficientes para atender esos nuevos gastos, por lo cual, tal como se demuestra en recientes estudios y an\u00e1lisis estad\u00edsticos sobre la congesti\u00f3n en el Consejo de Estado, el volumen de asuntos que se han venido represando en la Sala Plena Contenciosa y en las secciones, exigen la adopci\u00f3n de medidas de urgencia que faciliten la toma de decisiones en forma oportuna y eficaz.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cCon este proyecto se busca, de una parte, poner en vigencia inmediata la repartici\u00f3n de competencias que la Ley 446 determin\u00f3 entre los Tribunales Administrativos y el Consejo de Estado a fin de que lleguen en segunda instancia a este \u00faltimo solo aquellos asuntos que por su cuant\u00eda as\u00ed lo ameriten de acuerdo con los criterios ya se\u00f1alados por el legislador desde 1998. Y, de otra, establecer el mecanismo adecuado para que la Sala Plena Contencioso Administrativa evac\u00fae el trabajo que se ha venido acumulando en relaci\u00f3n con los recursos de s\u00faplica interpuestos, cuya decisi\u00f3n se ha venido desplazando por las competencias prioritarias que la Constituci\u00f3n le asign\u00f3, y se evite en el futuro la repetici\u00f3n de esta situaci\u00f3n que dificulta y obstaculiza el normal funcionamiento de la Corporaci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cEste proyecto tiene la virtud de facilitar la descongesti\u00f3n del Consejo de Estado, aplicando criterios ya definidos por el legislador, sin que se genere ning\u00fan costo adicional en su funcionamiento, pues es de todos conocida la dif\u00edcil situaci\u00f3n econ\u00f3mica y fiscal del pa\u00eds que impedir\u00eda la adopci\u00f3n de medidas que impliquen un mayor costo. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cActualmente figuran enlistados 1.179 recursos extraordinarios de s\u00faplica, interpuestos contra los fallos proferidos por las cinco secciones que integran la Sala, aparte de las solicitudes de p\u00e9rdida de investidura de congresistas, impedimentos de magistrados de los Tribunales Administrativos, recursos extraordinarios de revisi\u00f3n, conflictos de competencias entre los tribunales administrativos, conflictos de competencias entre autoridades que ejercen funciones administrativas, y asuntos que, por importancia jur\u00eddica, remiten las secciones, todo lo cual implica que la resoluci\u00f3n de los recursos existentes, de seguir la situaci\u00f3n como hasta ahora, demorar\u00e1 varios a\u00f1os. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cEste problema, aunado al continuo crecimiento de la interposici\u00f3n de recursos extraordinarios y de los dem\u00e1s procesos, justifican la urgencia en la adopci\u00f3n de medidas inmediatas que permitan disminuir el volumen de asuntos que, hoy, son de conocimiento de la Sala Plena. De lo contrario, la evacuaci\u00f3n de la mayor parte de los procesos contencioso administrativos se har\u00e1 muy dispendiosa, lo cual atenta contra los principios de celeridad y eficacia que deben orientar la administraci\u00f3n de justicia, en el entendido de que, si bien la Constituci\u00f3n impone a los encargados de administrar el cumplimiento pronto y efectivo de sus deberes, para el juez resulta imposible ajustarse a los t\u00e9rminos procesales, teniendo en cuenta la responsabilidad que significan sus decisiones tanto en la definici\u00f3n misma de la controversia como en la adopci\u00f3n de derroteros jurisprudenciales. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cPor ello, en este proyecto se proponen f\u00f3rmulas como la eliminaci\u00f3n del recurso extraordinario de s\u00faplica -cuya ineficacia pr\u00e1ctica est\u00e1 ampliamente demostrada y, en cambio, ha servido para crear una grave congesti\u00f3n en la Sala-; el traslado de competencias, en ocasiones, a la Sala de Consulta y Servicio Civil, y en otras, a las diferentes Secciones; y la integraci\u00f3n de Salas Especiales Transitorias, dentro de la Sala Plena, encargadas de decidir los recursos existentes. Estas alternativas son descritas a continuaci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u201c(\u2026) \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cLas estad\u00edsticas que se anexan a esta exposici\u00f3n de motivos demuestran una verdad irrefutable: la inutilidad del Recurso Extraordinario de S\u00faplica, si se tiene en cuenta que la casi totalidad de los recursos fallados hasta la fecha ha confirmado los fallos recurridos. Ello produce, en cambio, una congesti\u00f3n innecesaria de trabajo en la Sala Plena de lo Contencioso Administrativo. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cSi bien el recurso est\u00e1 previsto como una revisi\u00f3n del trabajo de la Secci\u00f3n Especializada de la Sala Plena, por parte de quienes no son especialistas en el tema, no puede equipararse al Recurso Extraordinario de Casaci\u00f3n, pues en este la Corte Suprema de Justicia revisa las sentencias de los Tribunales Superiores de Distrito Judicial, en tanto que el Recurso Extraordinario de S\u00faplica genera una revisi\u00f3n de la sentencia por quienes son pares del fallador\u201d.9 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La Sala debe se\u00f1alar, por una parte, que el mecanismo de unificaci\u00f3n de la jurisprudencia no desaparece con la decisi\u00f3n legislativa adoptada, ya que en adelante dicha funci\u00f3n deber\u00e1 ser cumplida por cada una de las secciones de la Sala de lo Contencioso Administrativo del Consejo de Estado, en el ejercicio de sus funciones propias, lo cual se justifica por su car\u00e1cter especializado de conformidad con el reglamento de dicha corporaci\u00f3n10, y, por otra parte, que los motivos tenidos en cuenta por el legislador son constitucionalmente leg\u00edtimos y se ci\u00f1en a los criterios de razonabilidad y proporcionalidad. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Igualmente, debe tenerse en cuenta que, a pesar de la medida adoptada, subsiste la posibilidad de que la Sala de lo Contencioso Administrativo del Consejo de Estado conozca de determinados asuntos y unifique por esa v\u00eda la jurisprudencia, de acuerdo con lo dispuesto en el Art. 130 del C. C. A., modificado por el Art. 38 de la Ley 446 de 1998, en virtud del cual \u201ca solicitud del Ministerio P\u00fablico, o de oficio, las Secciones podr\u00e1n remitir a la Sala Plena de lo Contencioso Administrativo aquellos asuntos que se encuentren para fallo y que por su importancia jur\u00eddica o trascendencia social ameriten ser decididos por \u00e9sta. La Sala Plena decidir\u00e1 si avoca o no el conocimiento del asunto.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cIgualmente, la Sala Plena podr\u00e1 asumir directamente el conocimiento de los asuntos que se encuentren para fallo en cualquiera de las Secciones.\u201d\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por estas razones, la Corte concluye que la norma demandada no vulnera los derechos a la igualdad, el acceso a la administraci\u00f3n de justicia, el debido proceso y los principios de unidad del ordenamiento jur\u00eddico, seguridad jur\u00eddica y confianza leg\u00edtima. Por tanto, la declarar\u00e1 exequible, por los cargos analizados en esta sentencia. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>VII. DECISION\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Plena de la Corte Constitucional, administrando justicia en nombre del pueblo y por mandato de la Constituci\u00f3n, \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0R E S U E L V E: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Primero.- ESTARSE A LO RESUELTO en la Sentencia C-1233 de 2005, que declar\u00f3 EXEQUIBLE el segmento normativo \u201cque, a la fecha de entrada en vigencia de la presente ley, tengan proferido el respectivo auto admisorio\u201d, contenido en el art\u00edculo 3o, transitorio, de la Ley 954 de 2005. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Segundo.- DECLARARSE INHIBIDA para proferir decisi\u00f3n de m\u00e9rito respecto de la demanda de inconstitucionalidad contra el Art. 3\u00ba de la Ley 954 de 2005, en la parte no revisada en la Sentencia C-1233 de 2005, por ineptitud sustantiva de la demanda. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Tercero.- DECLARAR EXEQUIBLE el Art. 2\u00ba de la Ley 954 de 2005, por los cargos analizados en esta sentencia.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese, ins\u00e9rtese en la Gaceta de la Corte Constitucional, c\u00famplase y arch\u00edvese el expediente. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>MANUEL JOSE CEPEDA ESPINOSA \u00a0<\/p>\n<p>Presidente \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>JAIME ARAUJO RENTERIA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ALFREDO BELTRAN SIERRA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>JAIME CORDOBA TRIVI\u00d1O \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>RODRIGO ESCOBAR GIL \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>AUSENTE CON PERMISO \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>MARCO GERARDO MONROY CABRA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>HUMBERTO ANTONIO SIERRA PORTO \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ALVARO TAFUR GALVIS \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>CLARA INES VARGAS HERNANDEZ \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>MARTHA VICTORIA SACHICA DE MONCALEANO \u00a0<\/p>\n<p>Secretaria General \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>Produced by the free evaluation copy of TotalHTMLConverter<\/p>\n<p>2 Sentencia C-131 de 1993, M. P. Alejandro Mart\u00ednez Caballero. \u00a0<\/p>\n<p>3 Cfr. Sentencias C- 561\/04, M.P. Manuel Jos\u00e9 Cepeda Espinosa; C-965\/03, M.P. Rodrigo Escobar Gil; C-878\/00, M.P. Alfredo Beltr\u00e1n Sierra; C-803\/00, M.P. Alfredo Beltr\u00e1n Sierra; C-373\/95, M.P. Carlos Gaviria D\u00edaz, y C- 537\/93, M.P. Hernando Herrera Vergara. \u00a0<\/p>\n<p>4 Cfr. C- 965\/03, M.P. Rodrigo Escobar Gil \u00a0<\/p>\n<p>5 Sentencia C-880 de 2005, M. P. Jaime C\u00f3rdoba Trivi\u00f1o. \u00a0<\/p>\n<p>6 Sentencias C-742 de 1999, C-384 de 2000, \u00a0C-803 de 2000, entre otras. \u00a0<\/p>\n<p>7 Sentencia C-728 de 2000 \u00a0<\/p>\n<p>8 Sentencia C-1104 de 2001, M. P. Clara In\u00e9s Vargas Hern\u00e1ndez; \u00a0Salvamento de Voto de Alvaro Tafur G\u00e1lvis. \u00a0<\/p>\n<p>9 Proyecto de ley 194 de 2004 Senado, Gaceta del Congreso No. 76 de Marzo 18 de 2004. \u00a0<\/p>\n<p>10 Conforme a lo dispuesto en el Acuerdo No. 58 de 1999, expedido por la Sala Plena del Consejo de Estado y que contiene el reglamento de dicha corporaci\u00f3n, \u201ccada secci\u00f3n ejercer\u00e1 separadamente las funciones que de conformidad con su especialidad y cantidad de trabajo le asigne la Sala Plena del Consejo de Estado de acuerdo con la ley\u201d (Art. 11). \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia C-180\/06 \u00a0 \u00a0\u00a0 INHIBICION DE LA CORTE CONSTITUCIONAL POR INEPTITUD SUSTANTIVA DE LA DEMANDA-Ausencia de cargos \u00a0 \u00a0\u00a0 RESERVA DE LEY ESTATUTARIA EN MATERIA DE JUSTICIA-No vulneraci\u00f3n al suprimir recurso extraordinario de s\u00faplica \u00a0 \u00a0\u00a0 La norma demandada no regula la estructura de la administraci\u00f3n de justicia ni los principios generales para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-12921","post","type-post","status-publish","format-standard","hentry","category-sentencias-2006"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/12921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=12921"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/12921\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=12921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=12921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=12921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}