{"id":142,"date":"2024-05-30T15:21:32","date_gmt":"2024-05-30T15:21:32","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/05\/30\/t-474-92\/"},"modified":"2024-05-30T15:21:32","modified_gmt":"2024-05-30T15:21:32","slug":"t-474-92","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-474-92\/","title":{"rendered":"T 474 92"},"content":{"rendered":"<p>T-474-92<\/p>\n<p>&nbsp; &nbsp; Sentencia No. T-474\/92 &nbsp;<\/p>\n<p>DEBIDO PROCESO\/RESOLUCION DE ACUSACION-Circunstancias agravantes &nbsp;<\/p>\n<p>La doctrina que no reconoce la obligaci\u00f3n &#8211; cuya violaci\u00f3n entra\u00f1a nulidad constitucional &#8211; de mencionar expresamente en todos los casos las circunstancias espec\u00edficas de agravaci\u00f3n punitiva en el pliego de cargos, no se ajusta a las previsiones de la Constituci\u00f3n. En atenci\u00f3n a los efectos de un mayor o menor t\u00e9rmino de privaci\u00f3n de la libertad, a la necesidad de una adecuada y expl\u00edcita informaci\u00f3n sobre los cargos que se le imputan a un sindicado para hacer operar en toda su magnitud la presunci\u00f3n de inocencia y a la carga probatoria en cabeza de la parte acusadora, la exigencia de hacer expl\u00edcitas las circunstancias espec\u00edficas de agravaci\u00f3n en el auto o resoluci\u00f3n de acusaci\u00f3n es la m\u00e1s acorde con las garant\u00edas sustanciales y procesales consignadas en el art\u00edculo 29 de la Constituci\u00f3n, al permitir que el sindicado, con la asistencia de su abogado, planee y ejecute aut\u00f3noma e integralmente su defensa. &nbsp;<\/p>\n<p>PRINCIPIO NO REFORMATIO IN PEJUS\/PREVALENCIA DEL DERECHO SUSTANCIAL &nbsp;<\/p>\n<p>La interdicci\u00f3n de la reforma en perjuicio del condenado constituye, igualmente, una garant\u00eda procesal fundamental del r\u00e9gimen de los recursos, a su vez contenido en el derecho de defensa y en el n\u00facleo esencial del derecho al debido proceso. Al superior no le es dable por expresa prohibici\u00f3n constitucional empeorar la pena impuesta al apelante \u00fanico, porque al fallar ex-officio sorprende al recurrente, quien formalmente por lo menos no ha tenido la posibilidad de conocer y controvertir los motivos de la sanci\u00f3n a \u00e9l impuesta, oper\u00e1ndose por esta v\u00eda &nbsp;una situaci\u00f3n de indefensi\u00f3n. Una decisi\u00f3n m\u00e1s gravosa de la pena impuesta al condenado y apelante \u00fanico que desestime dichas limitaciones, vulnera los derechos fundamentales de defensa y debido proceso, por lo cual debe ser exclu\u00edda del ordenamiento jur\u00eddico. La interpretaci\u00f3n constitucional del art\u00edculo 31 de la Carta debe inspirarse en su finalidad garantista y en la primac\u00eda del derecho sustancial sobre meras consideraciones y acentos formalistas. En efecto, la expresi\u00f3n &#8220;apelante \u00fanico&#8221;, requisito necesario para limitar las facultades del juez de segunda instancia, no hace relaci\u00f3n exclusiva al n\u00famero de recurrentes de la sentencia condenatoria, sino a la naturaleza de sus pretensiones. La reformatio in peius tambi\u00e9n se extiende a lo civil: al Juez o Tribunal de segunda instancia le est\u00e1 vedado decretar la responsabilidad civil que supere el l\u00edmite de lo ya acordado en la primera instancia, sin obrar la correspondiente petici\u00f3n . &nbsp;<\/p>\n<p>ACCION DE TUTELA CONTRA SENTENCIAS\/ACCION DE REVISION-Improcedencia &nbsp;<\/p>\n<p>Si el art\u00edculo 86 de la Constituci\u00f3n hubiera sustra\u00eddo de la acci\u00f3n de tutela la sentencias de los jueces, en todo caso se habr\u00eda hecho necesario aplicarla, por entra\u00f1ar tales derechos garant\u00edas inherentes a la persona humana. La denominada &#8220;acci\u00f3n de revisi\u00f3n&#8221; de la Corte Suprema de Justicia, establecida para revisar sentencias cuando se comprueben casos de prevaricato por parte del fallador, no es un medio alternativo de defensa judicial en este caso. Verificada la violaci\u00f3n de los derechos fundamentales mencionados, por parte de la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, procede revocar la sentencia denegatoria de la tutela emanada de la Sala Plena y que es materia de revisi\u00f3n. El car\u00e1cter manifiesto de la vulneraci\u00f3n, unido a la \u00edndole inhibitoria de la sentencia de tutela dictada por la Sala Plena de la Corte Suprema de Justicia, lleva a esta Corporaci\u00f3n a disponer la protecci\u00f3n inmediata de los derechos constitucionales fundamentales conculcados, para lo cual se revocar\u00e1 parcialmente la sentencia de la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal. &nbsp;<\/p>\n<p>JULIO 29 DE 1992 &nbsp;<\/p>\n<p>REF: Expediente T-1270 &nbsp;<\/p>\n<p>Actor: MOISES TUATY ALEXANDER &nbsp;<\/p>\n<p>Magistrados Ponentes: &nbsp;<\/p>\n<p>Dr. EDUARDO CIFUENTES MU\u00d1OZ &nbsp;<\/p>\n<p>Dr. ALEJANDRO MARTINEZ CABALLERO &nbsp;<\/p>\n<p>La Sala Segunda de Revisi\u00f3n de la Corte Constitucional, integrada por los Magistrados Eduardo Cifuentes Mu\u00f1oz, Jos\u00e9 Gregorio Hern\u00e1ndez Galindo y Alejandro Mart\u00ednez Caballero, ha pronunciado &nbsp;<\/p>\n<p>EN NOMBRE DEL PUEBLO&nbsp; &nbsp;<\/p>\n<p>&nbsp;Y &nbsp;<\/p>\n<p>&nbsp; POR MANDATO &nbsp;DE LA CONSTITUCION &nbsp;<\/p>\n<p>la siguiente &nbsp;<\/p>\n<p>En el proceso de tutela T-1270 adelantado por el &nbsp;se\u00f1or &nbsp;MOISES TUATY ALEXANDER contra la sentencia de la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, del 9 de octubre de 1991, proferida en el proceso penal &nbsp;contra el se\u00f1or MOISES TUATY ALEXANDER por el delito de tentativa de estafa. &nbsp;<\/p>\n<p>A N T E C E D E N T E S&nbsp; &nbsp;<\/p>\n<p>1. El Juzgado Octavo Superior de Bogot\u00e1, mediante auto del 23 de Julio de 1987, llam\u00f3 a responder en juicio criminal al procesado MOISES TUATY ALEXANDER como coautor de los delitos de Falsedad en Documentos y Estafa. Apelada esta decisi\u00f3n, el Tribunal Superior dispuso su revocatoria en cuanto al delito de falsedad, sobreseyendo temporalmente al procesado, y confirm\u00e1ndola en relaci\u00f3n con la tentativa de estafa. &nbsp;<\/p>\n<p>2. Adelantado el juicio penal, el Juzgado Cuarto Penal del Circuito de Bogot\u00e1, mediante sentencia del 12 de mayo de 1989, conden\u00f3 a MOISES TUATY ALEXANDER a la pena principal de dieciocho (18) meses de prisi\u00f3n y multa de diez mil pesos como responsable del delito de estafa en la modalidad de tentativa, concedi\u00e9ndole de otra parte el subrogado de condena de ejecuci\u00f3n condicional. Adicionalmente, se le impuso la pena accesoria de interdicci\u00f3n de derechos y funciones p\u00fablicas por un t\u00e9rmino igual al de la pena principal y el pago de da\u00f1os y perjuicios por un mill\u00f3n trescientos treinta y ocho mil trescientos nueve pesos con setenta y dos centavos ($1.338.309.72). En el fallo, el juez de primera instancia se pronunci\u00f3 sobre la dosificaci\u00f3n de la pena y expres\u00f3 lo siguiente: &nbsp;<\/p>\n<p>&#8220;No hacemos referencia a las circunstancias de agravaci\u00f3n (por la cuant\u00eda y la naturaleza del ente afectado &#8211; agrega esta Corte -) que coment\u00f3 el doctor Vicente Emilio Gaviria Londo\u00f1o, apoderado de la parte civil, por cuanto en el auto de proceder \u00e9stos no fueron formulados, luego la condenaci\u00f3n no estar\u00eda en consonancia con los cargos enunciados en el llamamiento a juicio&#8221;.&nbsp; &nbsp;<\/p>\n<p>3. La apoderada de MOISES TUATY ALEXANDER, interpuso recurso de APELACION contra la providencia condenatoria. Igualmente lo hizo el apoderado de la parte civil en representaci\u00f3n del Banco de la Rep\u00fablica, pero s\u00f3lo con el objeto de que se modificara el numeral tercero de la sentencia impugnada, por no haber sido condenado el procesado al pago de los perjuicios morales ocasionados con la comisi\u00f3n del il\u00edcito penal. &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>4. La Sala Penal del Tribunal Superior del Distrito Judicial de Bogot\u00e1 mediante sentencia del 15 de agosto de 1989, revoc\u00f3 en todas sus partes la sentencia de primera instancia y absolvi\u00f3 a MOISES TUATY ALEXANDER. En su sentencia el Tribunal se\u00f1al\u00f3:&nbsp; &nbsp;<\/p>\n<p>&#8220;No se niega que hay una serie de circunstancias no muy bien dilucidadas, tal como se dej\u00f3 consignado atr\u00e1s, que en un momento dado permitieron deducir como indicios graves para apuntalar la responsabilidad de TUATY en el auto de proceder. Pero ya hemos visto que la mayor\u00eda de circunstancias se orientan solamente hacia el indicio de mentira, el que reanalizado profundamente, no puede tenerse como indicio necesario, porque para ello se requiere que sea tal la correspondencia y la relaci\u00f3n entre los hechos, que habiendo existido el uno, no puede menos que haber existido el otro&#8221;. (Folio 78) &nbsp;<\/p>\n<p>5. Inconforme con la sentencia absolutoria, el apoderado de la parte civil interpuso recurso de casaci\u00f3n con apoyo en la causal primera, como &nbsp;consecuencia del error de hecho en que habr\u00eda incurrido el Tribunal en su versi\u00f3n de falso juicio de identidad, al limitar, modificando su contenido, la declaraci\u00f3n y documentaci\u00f3n presentada por el doctor NILSON PINILLA PINILLA, funcionario investigador del Banco de la Rep\u00fablica. &nbsp;<\/p>\n<p>El Procurador Tercero Delegado en lo Penal y la apoderada de MOISES TUATY ALEXANDER se opusieron en su momento al recurso interpuesto y solicitaron que \u00e9ste fuera desechado. &nbsp;<\/p>\n<p>6. La Sala de Casaci\u00f3n Penal de la Honorable Corte Suprema de Justicia, en sentencia del 9 de octubre de 1991, cas\u00f3 la decisi\u00f3n absolutoria del Tribunal Superior y conden\u00f3 a MOISES TUATY ALEXANDER a la pena de cuatro a\u00f1os y 2 meses de prisi\u00f3n y cien mil pesos de multa como responsable del delito de estafa en la modalidad de tentativa. Adem\u00e1s, le impuso la pena accesoria de interdicci\u00f3n de derechos y funciones p\u00fablicas por un t\u00e9rmino igual al de la pena principal y lo conden\u00f3 al pago de cuatro millones trescientos treinta y ocho mil trescientos nueve pesos con setenta y dos centavos ($4.338.309.72) por concepto de perjuicios ocasionados como consecuencia de la acci\u00f3n delictiva.&nbsp; &nbsp;<\/p>\n<p>La Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, acogi\u00f3 las tesis del recurrente. En su sentencia anot\u00f3: &nbsp; &nbsp;<\/p>\n<p>&#8220;De acuerdo con esto, la figuraci\u00f3n de la cuenta de TUATY en el desarrollo de su actividad il\u00edcita, como receptora final de los dineros fruto del fraude, lo cual aparece ampliamente acreditado con las copias de las \u00f3rdenes de traslado de las cuentas en Miami, hace indiscutible que de acuerdo con el respectivo plan de autores era acto necesario en la defraudaci\u00f3n propuesta. &nbsp;<\/p>\n<p>&#8220;En este orden de ideas, claro resulta que las exculpaciones en torno al por qu\u00e9 de la intervenci\u00f3n de TUATY en el proyecto de desposesi\u00f3n il\u00edcita de la cantidad de d\u00f3lares ampliamente referida en esta decisi\u00f3n, de la cual se pretend\u00eda hacer v\u00edctima al Banco de la Rep\u00fablica, no poseen la virtualidad de quitarle fuerza probatoria a los varios indicios, incluido el de mentira que viene de examinarse, sobre la responsabilidad como coautor de la tentativa de estafa juzgada. &#8230; &nbsp;<\/p>\n<p>&#8220;As\u00ed, entonces, debe concluirse el car\u00e1cter ostensible de los yerros del Tribunal en el fallo recurrido, raz\u00f3n por la cual ha de disponerse su casaci\u00f3n, para en su lugar, al dictar la respectiva sentencia de reemplazo, condenar a MOISES TUATY ALEXANDER como coautor de delito de estafa en forma de tentativa, por reunirse las exigencias contempladas en el art\u00edculo 215 del C. de P.P., aplicable al caso. &nbsp;<\/p>\n<p>&#8220;Para efectos de la tasaci\u00f3n de la pena, debe tenerse en cuenta que en contra de TUATY ALEXANDER militan las circunstancias de mayor punibilidad, de car\u00e1cter espec\u00edfico la del ordinal 1o. del art\u00edculo 372 del C\u00f3digo Penal que, no obstante no haber sido deducida en el auto de proceder, por su objetividad evidente y no cuestionamiento en el desarrollo de la causa se hace concurrente, y las de car\u00e1cter gen\u00e9rico de los numerales 4o. y 7o. del art\u00edculo 66 ib\u00eddem&#8221;. &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>En relaci\u00f3n con la anterior sentencia de casaci\u00f3n, salv\u00f3 su voto el H. Magistrado doctor JORGE ENRIQUE VALENCIA, quien adujo lo siguiente:&nbsp; &nbsp;<\/p>\n<p>&#8220;Invariablemente he venido sosteniendo en SALA PENAL que las circunstancias de agravaci\u00f3n punitiva perge\u00f1adas en el art\u00edculo 66 del C\u00f3digo Penal, deben ser deducidas en el auto que califica el m\u00e9rito del sumario y en jam\u00e1s de los jamases en el cuerpo de la sentencia, so pena de quebrantar el derecho de defensa. Como este criterio lo rechaza la mayor\u00eda me veo precisado en manifestar mi voto disidente. En este aspecto, me remito a la dial\u00e9ctica contenida en mis anteriores salvamentos de voto&#8221;. &nbsp;<\/p>\n<p>7. Posteriormente, el condenado MOISES TUATY ALEXANDER, interpuso acci\u00f3n de tutela contra la sentencia de la Sala de Casaci\u00f3n Penal de la Corte Suprema de Justicia, por considerarla violatoria de los art\u00edculos 29 (derecho al debido proceso) y 31 (reformatio in peius) de la Constituci\u00f3n. En su escrito sustentatorio, el apoderado del accionante, doctor JOSE MARIA VELASCO GUERRERO, asevera respecto a la violaci\u00f3n del derecho al debido proceso: &nbsp;<\/p>\n<p>&#8220;Lo anterior vale tanto como decir que &#8211; seg\u00fan lo afirma la Sala de Casaci\u00f3n Penal &#8211; puede el sentenciador sorprender al sindicado con &#8220;deducciones evidentes, no cuestionadas en el desarrollo de la causa&#8221; y agravarle la pena, a su talante y a espaldas de la defensa, que no tuvo ocasi\u00f3n, en ning\u00fan momento, de controvertir aquellas agravantes que ciertamente no le fueron deducidas en el auto de proceder. Y que no pod\u00edan deduc\u00edrsele en la sentencia, si esta debe dictarse en consonancia con aquel. Por ello suscribi\u00f3 salvedad de voto el honorable Magistrado Jorge Enrique Valencia M. Considera \u00e9l que por dicho modo el sentenciador viol\u00f3 los derechos de la defensa que, como garant\u00eda suya fundamental, consagra el Art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica vigente&#8221;. &nbsp;<\/p>\n<p>M\u00e1s adelante en su escrito, el petente alega la violaci\u00f3n de sus garant\u00edas constitucionales que lo amparaban en su condici\u00f3n de apelante \u00fanico:&nbsp; &nbsp;<\/p>\n<p>&#8220;A la Corte le estaba vedado &#8211; sostiene el doctor JOSE MARIA VELASCO GUERRERO &#8211; constitucionalmente agravar la situaci\u00f3n jur\u00eddica del sindicado. O, mejor a\u00fan, dicho en palabras del ya transcrito Art\u00edculo 31: &#8220;el superior no podr\u00e1 agravar la pena cuando el sindicado sea apelante \u00fanico&#8221;. Este es derecho fundamental suyo, de car\u00e1cter inviolable. -Sobra decir que el recurso extraordinario de casaci\u00f3n, por su naturaleza, difiere ostensiblemente del recurso ordinario de apelaci\u00f3n, a cuyo amparo tampoco puede la justicia infringir las prohibiciones de nuestro Estatuto Superior que protegen los derechos fundamentales&#8221;. &nbsp;<\/p>\n<p>8. Del anterior recurso conoci\u00f3 la Sala Plena de la Corte Suprema de Justicia. En sentencia del 30 de enero de 1992, deneg\u00f3 la tutela solicitada. La decisi\u00f3n de la Sala Plena se bas\u00f3 fundamentalmente en la sentencia del 9 de diciembre de 1991 proferida por la Sala de Casaci\u00f3n Civil de la misma Corporaci\u00f3n. Expone la Sala Plena en la parte motiva de la sentencia denegatoria: &nbsp;<\/p>\n<p>&#8220;En el sub-lite MOISES TUATY ALEXANDER invoca acci\u00f3n de tutela en raz\u00f3n de que la Sala de Casaci\u00f3n Penal le agrav\u00f3 su situaci\u00f3n jur\u00eddica al revocar el fallo absolutorio emitido por el Tribunal Superior del Distrito Judicial de Bogot\u00e1, quien a su vez revoc\u00f3 el fallo del Juzgado Cuarto Penal del Circuito de Bogot\u00e1. Como esta Sala es distinta de aquella que cas\u00f3 la sentencia del Tribunal y aument\u00f3 la pena impuesta por el Juzgado Cuarto Penal del Circuito de Bogot\u00e1, pero no su superior jer\u00e1rquico, aunque haya actuado en sede de instancia o como \u00f3rgano de apelaci\u00f3n, no puede atenderse la acci\u00f3n de tutela por existir contradicci\u00f3n e incompatibilidad entre los preceptos constitucionales y el art\u00edculo 40 del citado Decreto en los puntos arriba referidos, pues que, reit\u00e9rase, la Sala Plena de la Corte no es superior jer\u00e1rquico de ninguna de sus salas especializadas. Por consiguiente, conforme con lo explicado, la petici\u00f3n debe negarse&#8221;.&nbsp; &nbsp;<\/p>\n<p>10. Impugnada la decisi\u00f3n de la Sala Plena, el recurso de apelaci\u00f3n fue desechado mediante auto del 5 de marzo de 1992 con la advertencia de que &#8220;por tratarse de una sentencia de Sala Plena contra esa decisi\u00f3n no procede recurso alguno&#8221;, siendo en consecuencia remitida a la Corte Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>11. Seleccionada la sentencia de tutela para revisi\u00f3n, correspondi\u00f3 a esta Sala su conocimiento. &nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>FUNDAMENTOS JURIDICOS &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>Cargos contra la sentencia &nbsp;<\/p>\n<p>1. Dos son los cargos contra la sentencia de la honorable Sala de Casaci\u00f3n Penal de la Corte Suprema de Justicia objeto de la presente acci\u00f3n de tutela. El primero se refiere a la vulneraci\u00f3n de los derechos de defensa y al debido proceso (CP art. 29) por la incongruencia entre el auto de llamamiento a juicio (hoy resoluci\u00f3n de acusaci\u00f3n) proferido por el Juzgado Octavo Superior de Bogot\u00e1 y la sentencia de casaci\u00f3n que finalmente condenara al procesado MOISES TUATY ALEXANDER. El segundo cargo hace relaci\u00f3n con el desconocimiento de la prohibici\u00f3n que impide al superior agravar la pena impuesta al condenado cuando \u00e9ste es apelante \u00fanico, consagrada en el art\u00edculo 31 de Constituci\u00f3n Pol\u00edtica, por parte de la Sala de Casaci\u00f3n Penal al fallar como tribunal de instancia. &nbsp;<\/p>\n<p>Derecho al debido proceso y derecho de defensa &nbsp;<\/p>\n<p>2. Anteriormente contenido en el art\u00edculo 26 de la Constituci\u00f3n de 1886, el derecho al debido proceso est\u00e1 consagrado de manera ampliada en el art\u00edculo 29 de la nueva Constituci\u00f3n. Su relevancia constitucional obedece a que representa la m\u00e1xima facultad y posibilidad del individuo para limitar el ius puniendi del Estado. El derecho fundamental del debido proceso es de aplicaci\u00f3n inmediata (CP art. 85), vincula a todas las autoridades y constituye una garant\u00eda de legalidad procesal para proteger la libertad, la seguridad jur\u00eddica, la racionalidad y la fundamentaci\u00f3n de las resoluciones judiciales.&nbsp; &nbsp;<\/p>\n<p>El derecho al debido proceso comprende un conjunto de principios materiales y &nbsp;formales entre los que se encuentran el principio de legalidad (nemo iudex sine lege), el principio del juez natural o juez legal, el principio de favorabilidad penal y el principio de presunci\u00f3n de inocencia, todos los cuales en estricto rigor responden mejor a la estructura jur\u00eddica de verdaderos derechos fundamentales. El art\u00edculo 29 de la Carta contempla, adem\u00e1s, otros derechos que se entienden contenidos en el n\u00facleo esencial del derecho al debido proceso, como son el derecho de defensa, el derecho de asistencia de un abogado, el derecho a un debido proceso sin dilaciones injustificadas, el derecho a presentar y controvertir pruebas, el derecho a impugnar la sentencia condenatoria y el derecho a no ser juzgado dos veces por el mismo hecho (non bis in idem). &nbsp;<\/p>\n<p>Concordancia entre el auto de proceder y la sentencia &nbsp;<\/p>\n<p>3. El principio de concordancia entre el auto de llamamiento a juicio o auto de proceder (hoy resoluci\u00f3n de acusaci\u00f3n) y la sentencia, ha sido entendido tradicionalmente como una de las garant\u00edas esenciales del procesado para dise\u00f1ar y ejercer adecuadamente su defensa. Del pliego de cargos, de su claridad y especificidad, depende la posibilidad de una defensa real y efectiva. La incongruencia entre estos dos momentos procesales conlleva la nulidad constitucional o legal de la sentencia, al mismo tiempo que constituye una causal de casaci\u00f3n (art. 15 num.2, D.L. 1861 de 1989; art. 220 del nuevo C.P.P.). &nbsp;<\/p>\n<p>La jurisprudencia de la Sala de Casaci\u00f3n Penal de la Corte Suprema de Justicia as\u00ed lo ha sostenido invariablemente al exigir que la elaboraci\u00f3n del pliego de cargos se someta al lleno de estrictos requisitos formales y sustanciales, cuya omisi\u00f3n aparejar\u00eda a la existencia de una nulidad. Al respecto ha dicho la Sala de Casaci\u00f3n Penal: &nbsp;<\/p>\n<p>&#8220;Es completamente cierto que la Corporaci\u00f3n de manera reiterada ha sostenido que la elaboraci\u00f3n del pliego de cargos no es una labor de actividad libre, sino que, por el contrario, se debe someter al lleno de los requisitos formales y sustanciales y entre ellos tiene especial trascendencia la precisi\u00f3n y claridad de los hechos que son motivo de investigaci\u00f3n y por los cuales se formula la imputaci\u00f3n de la misma manera que las circunstancias de tiempo, modo y lugar en que ocurrieron, y las de agravaci\u00f3n punitiva que hayan sido deducidas, la \u00e9poca de la ocurrencia de los hechos, la individualizaci\u00f3n o identificaci\u00f3n de los procesados y la calificaci\u00f3n jur\u00eddica de dichos hechos, providencia que en la parte motiva debe precisar con claridad en cuanto a la especie delictiva por la cual se formula la acusaci\u00f3n. &#8230; &nbsp;<\/p>\n<p>&#8220;El no cumplimiento de tan estrictas formalidades y requisitos llevar\u00eda a la existencia de una nulidad, no s\u00f3lo del debido proceso, sino del derecho de defensa, puesto que es claro que este \u00faltimo derecho de car\u00e1cter constitucional no es m\u00e1s que una especie de un exacto y debido proceso y se vulnerar\u00edan estos derechos por la existencia de un acto con formulaci\u00f3n de cargos anfibol\u00f3gicos, oscuros o contradictorios, puesto que no dar\u00eda posibilidades defensivas, al no saberse a ciencia cierta cu\u00e1les son los cargos de los cuales se debe defender&#8221;.1&nbsp; &nbsp;<\/p>\n<p>Resoluci\u00f3n de acusaci\u00f3n y circunstancias de agravaci\u00f3n punitiva &nbsp;<\/p>\n<p>4. La jurisprudencia penal no ha sido uniforme sobre la necesidad de consignar de manera expresa las circunstancias de agravaci\u00f3n punitiva en el auto de formulaci\u00f3n de cargos.&nbsp; &nbsp;<\/p>\n<p>Ante todo, debe distinguirse en esta materia entre las circunstancias espec\u00edficas y gen\u00e9ricas de agravaci\u00f3n punitiva. Las primeras hacen parte integrante de los tipos penales; las segundas, en cambio, est\u00e1n consagradas en la parte general del C\u00f3digo Penal y se predican de cualquiera de sus tipos penales. Esta diferencia tiene consecuencias jur\u00eddicas que han sido relievadas por la Sala de Casaci\u00f3n Penal de la Corte Suprema de Justicia: &nbsp;<\/p>\n<p>&#8220;Esta diferencia estructural entre las unas y las otras genera a su vez que las primeras por formar parte de los tipos y por referirse a la conducta del autor al calificar el tipo b\u00e1sico, deben imputarse en el auto de formulaci\u00f3n de cargos, de la misma manera que incluidas en el cuestionario presentado al jurado de conciencia y ello debe ser as\u00ed, porque como tiene especial trascendencia en cuanto a la responsabilidad y a la cuantificaci\u00f3n punitiva, es obvio que el procesado las debe conocer para poder defenderse de las mismas; pero no sucede igual con las gen\u00e9ricas, puesto que \u00e9stas s\u00f3lo se tienen en cuenta para los efectos de la dosificaci\u00f3n punitiva y por tanto s\u00f3lo son consideradas en el momento de dictar sentencia, puesto que no hacen parte de la estructura del delito. La Sala ha considerado la conveniencia de que las gen\u00e9ricas sean por lo menos mencionadas en el auto de formulaci\u00f3n de cargos&#8221;.2&nbsp; &nbsp;<\/p>\n<p>No obstante, en otra sentencia , casi coet\u00e1nea, la Sala de Casaci\u00f3n Penal sostuvo una tesis contraria al referirse a la necesidad de explicitar las circunstancias espec\u00edficas de agravaci\u00f3n en el auto de resoluci\u00f3n de acusaci\u00f3n. Dijo en aqu\u00e9lla oportunidad la Sala de Casaci\u00f3n Penal: &nbsp;<\/p>\n<p>&#8220;No es dable admitir que se dificult\u00f3 la defensa y que \u00e9sta se hizo inoperante o ineficaz, en cuanto a las agravaciones, por falta de entrenamiento de las mismas, por haber fallado la menci\u00f3n de los art\u00edculos 350-4; 351-6,9,10 y 372-1 del C. Penal. Menos invocar una ausencia de espec\u00edfico an\u00e1lisis de estos factores de intensificaci\u00f3n particularizante de la pena, porque la jurisprudencia ha entendido que esta es deficiencia que no trasciende del terreno de la irregularidad imposible de llevar a los extremos de la anulaci\u00f3n, pues cuando la afirmaci\u00f3n escueta &nbsp;(v.gr.: de noche, a las 21:50 horas; dos o m\u00e1s personas, en el caso de autos, etc.) corresponde a un hecho evidente o al menos protuberante, la falta de motivaci\u00f3n no tiene eficacia para dificultar la defensa. S\u00f3lo cuando esa ausencia de razones sea absoluta y recaiga sobre hechos que para conocerlos se deben desbrozar con ayuda de esfuerzo dial\u00e9ctico, puede hablarse de atropello efectivo del &nbsp;derecho de defensa&#8221;.3&nbsp; &nbsp;<\/p>\n<p>La disparidad de posiciones en torno a la necesidad de mencionar las circunstancias espec\u00edficas de agravaci\u00f3n en el pliego de cargos o resoluci\u00f3n de acusaci\u00f3n radica en que mientras algunas sentencias exigen prima facie su menci\u00f3n, dado el efecto que dicha calificaci\u00f3n punitiva puede tener en la calificaci\u00f3n del tipo y cuantificaci\u00f3n de la pena, otras la hacen depender de las caracter\u00edsticas del hecho constitutivo de agravaci\u00f3n, por considerar que si \u00e9ste es evidente u ostensible no se produce indefensi\u00f3n por la ausencia de su menci\u00f3n expl\u00edcita. &nbsp;<\/p>\n<p>Perspectiva constitucional del cuestionamiento jur\u00eddico penal aludido &nbsp;<\/p>\n<p>5. La pena privativa de la libertad es la m\u00e1s dr\u00e1stica intervenci\u00f3n del Estado en los derechos fundamentales del individuo, particularmente de sus derechos a la libertad y al libre desarrollo de su personalidad. Esta intervenci\u00f3n se proyecta mucho m\u00e1s all\u00e1 del tiempo de privaci\u00f3n de la libertad, sobre toda la vida posterior del condenado. Por ello, el contenido y caracter\u00edsticas de la pena y la manera de cuantificar su extensi\u00f3n tienen relevancia directa para el derecho constitucional. La prevalencia de la parte dogm\u00e1tica sobre la parte org\u00e1nica de la Constituci\u00f3n involucra el principio de la interpretaci\u00f3n m\u00e1s favorable para los derechos fundamentales. &nbsp;La interpretaci\u00f3n conforme a la Constituci\u00f3n se traduce, en materia penal, en la limitaci\u00f3n de las facultades y del poder punitivo del Estado, en el grado y en la extensi\u00f3n necesarias a fin de garantizar el debido proceso y los dem\u00e1s derechos constitucionales que la Carta consagra en favor de los procesados &nbsp;<\/p>\n<p>El principio de favorabilidad penal se encuentra ampliamente reforzado por el principio pro derechos fundamentales. El poder punitivo del Estado ha quedado sujeto, por virtud del nuevo ordenamiento constitucional, a m\u00e1s estrictas y precisas exigencias. Particularmente, en materia probatoria, la presunci\u00f3n de inocencia ha dejado de ser un principio general de derecho que informa la actividad judicial (in dubio pro reo) para convertirse en un derecho fundamental. &nbsp;<\/p>\n<p>El derecho fundamental a la presunci\u00f3n de inocencia, por su car\u00e1cter de presunci\u00f3n iuris tantum, s\u00f3lo puede ser desvirtuada merced a una m\u00ednima actividad probatoria; no puede, por tanto, trasladarse al acusado &#8220;la carga de probar su inocencia&#8221;, pues \u00e9sta inicialmente se presume como cierta hasta que no se demuestre lo contrario, de donde se infiere que la carga probatoria corresponde a los acusadores y la claridad y precisi\u00f3n de las acusaciones al Estado mismo4 . &nbsp;<\/p>\n<p>En este marco de referencia deben evaluarse las tesis antag\u00f3nicas de la jurisprudencia penal. La doctrina que no reconoce la obligaci\u00f3n &#8211; cuya violaci\u00f3n entra\u00f1a nulidad constitucional &#8211; de mencionar expresamente en todos los casos las circunstancias espec\u00edficas de agravaci\u00f3n punitiva en el pliego de cargos, no se ajusta a las previsiones de la Constituci\u00f3n. En atenci\u00f3n a los efectos de un mayor o menor t\u00e9rmino de privaci\u00f3n de la libertad, a la necesidad de una adecuada y expl\u00edcita informaci\u00f3n sobre los cargos que se le imputan a un sindicado para hacer operar en toda su magnitud la presunci\u00f3n de inocencia y a la carga probatoria en cabeza de la parte acusadora, la exigencia de hacer expl\u00edcitas las circunstancias espec\u00edficas de agravaci\u00f3n en el auto o resoluci\u00f3n de acusaci\u00f3n es la m\u00e1s acorde con las garant\u00edas sustanciales y procesales consignadas en el art\u00edculo 29 de la Constituci\u00f3n, al permitir que el sindicado, con la asistencia de su abogado, planee y ejecute aut\u00f3noma e integralmente su defensa. &nbsp;<\/p>\n<p>Vulneraci\u00f3n del derecho de defensa&nbsp; &nbsp;<\/p>\n<p>6. En el caso sub-examine, se ha vulnerado el derecho de defensa del peticionario por la decisi\u00f3n de la Sala de Casaci\u00f3n Penal de la Corte Suprema de Justicia de condenar al procesado a una pena mayor a la impuesta inicialmente a pesar de que en primera instancia expresamente se afirm\u00f3 por parte del juez que no se hac\u00eda referencia a las circunstancias de agravaci\u00f3n punitiva &#8220;por cuanto en el auto de proceder \u00e9stos no fueron formulados, luego la condenaci\u00f3n no estar\u00eda en consonancia con los cargos enunciados en el llamamiento a juicio&#8221;. &nbsp;<\/p>\n<p>La decisi\u00f3n de la Sala de Casaci\u00f3n Penal de hacer concurrir con el delito de estafa las circunstancias t\u00edpicas de agravaci\u00f3n (art. 372-1 C. Penal), &#8220;no obstante no haber sido deducida en el auto de proceder, por su objetividad evidente y no cuestionamiento en el desarrollo de la causa&#8221; &#8211; en palabras de la misma Corporaci\u00f3n -, vulner\u00f3 el derecho fundamental del debido proceso al haber afectado las posibilidades y alternativas de defensa del inculpado. No es de modo alguno descartable que el no cuestionamiento en el desarrollo de la causa de la circunstancia espec\u00edfica de agravaci\u00f3n indilgada pudo obedecer precisamente a su no inclusi\u00f3n en el auto de llamamiento a juicio proferido por el Juzgado Octavo Superior de Bogot\u00e1. La &#8220;evidencia y objetividad&#8221; de los hechos constitutivos de las causales espec\u00edficas de agravaci\u00f3n no son criterios suficientes para relevar al Estado de su obligaci\u00f3n de demostrar su ocurrencia, ni camino para trasladar, de manera sutil, la carga probatoria al sindicado. Su no inclusi\u00f3n en el pliego de cargos libera al procesado de toda obligaci\u00f3n de defensa, respecto a los mismos, por lo que resulta desproporcionado y sorpresivo finalmente condenarlo por el descuido o negligencia del Estado al configurar y formalizar la acusaci\u00f3n. Cabe aqu\u00ed se\u00f1alar que las reglas del derecho procesal representan el precio que se debe pagar por vivir en un estado democr\u00e1tico de derecho. &#8220;El Estado no puede (&#8230;) investigar la verdad a cualquier precio. Tiene que autolimitarse en lo que se denomina ejercicio de la funci\u00f3n jurisdiccional, es decir, en la aplicaci\u00f3n del derecho penal en un juicio ordenado penalmente, con el fin de no &#8220;igualarse&#8221; al delincuente, no caer en la barbarie, demostrando al p\u00fablico que \u00e9l va a &nbsp;enjuiciar objetiva e imparcialmente&#8221;.5&nbsp; &nbsp;<\/p>\n<p>La prohibici\u00f3n del art\u00edculo 31 de la Constituci\u00f3n. &nbsp;<\/p>\n<p>7. El art\u00edculo 31 de la Constituci\u00f3n viene a completar los derechos fundamentales consagrados en los art\u00edculos 28, 29 y 30. Su texto es el siguiente: &nbsp;<\/p>\n<p>&#8220;Toda sentencia judicial podr\u00e1 ser apelada o consultada, salvo las excepciones que consagre la ley. &nbsp;<\/p>\n<p>El superior no podr\u00e1 agravar la pena impuesta cuando el condenado sea apelante \u00fanico.&#8221; &nbsp;<\/p>\n<p>La consagraci\u00f3n en la Carta Pol\u00edtica de la prohibici\u00f3n de agravar la pena impuesta al condenado cuando \u00e9ste es apelante \u00fanico eleva a nivel constitucional la garant\u00eda de la proscripci\u00f3n de la &#8220;reformatio in peius&#8221; y proyecta su aplicaci\u00f3n al derecho penal.&nbsp; &nbsp;<\/p>\n<p>Definici\u00f3n y alcance de la &#8220;reformatio in peius&#8221; &nbsp;<\/p>\n<p>8. La prohibici\u00f3n de la &#8220;reformatio in peius&#8221; o reforma peyorativa es un principio general del derecho procesal y una garant\u00eda constitucional que hace parte del derecho fundamental al debido proceso (CP art. 29). Ella es consecuencia de la regla \u00ednsita en la m\u00e1xima latina &#8220;tantum devolutum quantum appelatum&#8221;, en virtud de la cual se ejerce la competencia del juez superior. El ejercicio de las competencias judiciales radicadas en el juez superior y su l\u00edmite, ambos, se suscitan y a la vez se limitan por virtud de la impugnaci\u00f3n y las pretensiones que ella involucra. &nbsp; &nbsp;<\/p>\n<p>La interdicci\u00f3n de la reforma en perjuicio del condenado constituye, igualmente, una garant\u00eda procesal fundamental del r\u00e9gimen de los recursos, a su vez contenido en el derecho de defensa y en el n\u00facleo esencial del derecho al debido proceso. Al superior no le es dable por expresa prohibici\u00f3n constitucional empeorar la pena impuesta al apelante \u00fanico, porque al fallar ex-officio sorprende al recurrente, quien formalmente por lo menos no ha tenido la posibilidad de conocer y controvertir los motivos de la sanci\u00f3n a \u00e9l impuesta, oper\u00e1ndose por esta v\u00eda &nbsp;una situaci\u00f3n de indefensi\u00f3n. &nbsp;<\/p>\n<p>Finalidad de la prohibici\u00f3n &nbsp;<\/p>\n<p>9. Adem\u00e1s de limitar el poder punitivo del Estado, de garantizar la efectividad del derecho fundamental de defensa y de favorecer al condenado con la revisi\u00f3n de la sentencia dentro del \u00fanico marco de las pretensiones solicitadas, la reformatio in peius extendida al plano penal, avala y garantiza la operancia del sistema acusatorio. En efecto, bajo la vigencia del sistema inquisitivo el juez desplegaba al mismo tiempo las facultades de investigaci\u00f3n y decisi\u00f3n, correspondi\u00e9ndole al superior amplias facultades de revisi\u00f3n en las instancias de apelaci\u00f3n y, con mayor medida, en ejercicio del control de legalidad que supone la casaci\u00f3n. El doble desempe\u00f1o del juez en dicho sistema reun\u00eda en una s\u00f3la las tareas de la acusaci\u00f3n y de juzgamiento, con lo cual la imparcialidad y objetividad del fallador estaban en tela de juicio. La implantaci\u00f3n del sistema acusatorio escinde definitivamente ambas funciones y restringe los poderes del juez en materia de investigaci\u00f3n y acusaci\u00f3n, las cuales corresponden primordialmente a la Fiscal\u00eda General de la Naci\u00f3n. La reformatio in peius refuerza el car\u00e1cter dispositivo y no &#8220;ex-officio&#8221; del sistema acusatorio e impone a los cuerpos judiciales superiores l\u00edmites en la esfera de su poder sancionatorio. &nbsp;<\/p>\n<p>La separaci\u00f3n entre los planos de la acusaci\u00f3n y del juzgamiento explica la estrecha relaci\u00f3n entre la prohibici\u00f3n del art\u00edculo 31 de la Carta y el derecho de defensa. Al proscribir el sistema acusatorio la indefensi\u00f3n, excluye igualmente toda posibilidad de reforma de la situaci\u00f3n jur\u00eddica definida en primera instancia que no sea consecuencia de una pretensi\u00f3n frente a la cual, aquel en cuyo da\u00f1o se produce tal reforma, no tenga ocasi\u00f3n de defenderse.&nbsp; &nbsp;<\/p>\n<p>10. De la prohibici\u00f3n contenida en el art\u00edculo 31 de la Constituci\u00f3n deriva la imposibilidad de un fallo extra-petita, el cual s\u00f3lo podr\u00eda constitucionalmente aceptarse si otras partes del proceso penal, dependiendo de la naturaleza de sus pretensiones, recurren la sentencia condenatoria. Aunque el recurso de apelaci\u00f3n suscita un &#8220;novum iudicium&#8221;, la libre facultad decisoria del fallador est\u00e1 sujeta a las limitaciones materiales que imponen las pretensiones elevadas por las partes. En estas condiciones, una decisi\u00f3n m\u00e1s gravosa de la pena impuesta al condenado y apelante \u00fanico que desestime dichas limitaciones, vulnera los derechos fundamentales de defensa y debido proceso, por lo cual debe ser exclu\u00edda del ordenamiento jur\u00eddico.&nbsp; &nbsp;<\/p>\n<p>La interpretaci\u00f3n constitucional del art\u00edculo 31 de la Carta debe inspirarse en su finalidad garantista y en la primac\u00eda del derecho sustancial sobre meras consideraciones y acentos formalistas. En efecto, la expresi\u00f3n &#8220;apelante \u00fanico&#8221;, requisito necesario para limitar las facultades del juez de segunda instancia, no hace relaci\u00f3n exclusiva al n\u00famero de recurrentes de la sentencia condenatoria, sino a la naturaleza de sus pretensiones.&nbsp; &nbsp;<\/p>\n<p>En el proceso penal actual son claramente distinguibles cuatro partes procesales: el acusado, la parte civil, el Ministerio P\u00fablico y la Fiscal\u00eda General de la Naci\u00f3n. Cualquiera de las tres \u00faltimas mencionadas puede pretender leg\u00edtimamente la condena del acusado; sin embargo, cuando las pretensiones de una de las partes se restringen al plano o inter\u00e9s econ\u00f3mico y son, por lo tanto, pretensiones de car\u00e1cter civil, el ejercicio de recursos en contra de la sentencia condenatoria no conduce a inobservar la interdicci\u00f3n peyorativa o reformatio in peius, salvo en lo relacionado con dicha pretensi\u00f3n. No basta que el juez ad-quem se limite a contabilizar el n\u00famero de partes recurrentes para concluir, eo ipso, la inexistencia de la prohibici\u00f3n constitucional por registrarse una pluralidad de apelantes. Por el contrario, el juzgador debe establecer la naturaleza de las pretensiones esgrimidas y conformar sus facultades decisorias a lo estrictamente permitido por la Constituci\u00f3n. Ser\u00eda absurdo, y a la vez inconstitucional, acabar agravando la condena de privaci\u00f3n de la libertad del procesado, si habiendo apelado la sentencia, el juez decide finalmente aumentar la pena principal por efecto de la pretensi\u00f3n concurrente, pero de naturaleza estrictamente econ\u00f3mica, &nbsp;elevada por la parte civil. &nbsp;<\/p>\n<p>Pretensiones de car\u00e1cter civil y penal &nbsp;<\/p>\n<p>11. La ocurrencia de un hecho constitutivo de delito genera la posibilidad de ejercer acciones penales o civiles, bien sea conjunta o separadamente. El car\u00e1cter independiente de las acciones legales no condiciona la existencia de una de ellas a la extinci\u00f3n de la otra. Sin embargo, cuando la acci\u00f3n civil se interpone en el curso de un proceso penal, esto conlleva consecuencias jur\u00eddicas para su ejercicio, siendo aplicable respecto a las pretensiones de la parte civil la limitante de la reformatio in peius. &nbsp;<\/p>\n<p>No se produce la lesi\u00f3n del art\u00edculo 31 de la Constituci\u00f3n e indirectamente del 29, cuando existe una pretensi\u00f3n de signo contrario pero de igual naturaleza, ejercitada por las partes, como en el caso de que la parte civil solicite la condena y el condenado la absoluci\u00f3n. De otra parte, la reformatio in peius tambi\u00e9n se extiende a lo civil: al Juez o Tribunal de segunda instancia le est\u00e1 vedado decretar la responsabilidad civil que supere el l\u00edmite de lo ya acordado en la primera instancia, sin obrar la correspondiente petici\u00f3n . &nbsp;<\/p>\n<p>Prevalencia de la interpretaci\u00f3n material o de fondo sobre la formal &nbsp;<\/p>\n<p>12. Los principios de interpretaci\u00f3n que privilegian el derecho sustancial sobre el procesal (CP art 228) y que otorgan primac\u00eda a los derechos fundamentales (CP art. 2, 85, 377) imponen de igual manera una interpretaci\u00f3n material y no simplemente formal de los art\u00edculos constitucionales que consagran o garantizan los derechos fundamentales. Es este el caso de la prohibici\u00f3n de reforma en perjuicio del condenado, la cual impide que con fundamento en el petitum estrictamente econ\u00f3mico de la parte civil, el \u00f3rgano judicial superior entienda franqueada la puerta para aumentar la sanci\u00f3n penal del procesado coloc\u00e1ndolo en situaci\u00f3n de indefensi\u00f3n que ri\u00f1e con el ordenamiento constitucional. &nbsp;<\/p>\n<p>Vulneraci\u00f3n del art\u00edculo 31 de la Constituci\u00f3n &nbsp; &nbsp;<\/p>\n<p>13. Aplicados los anteriores principios a la sentencia acusada, queda por clarificar si la prohibici\u00f3n de reforma peyorativa del art\u00edculo 31 de la Constituci\u00f3n es aplicable respecto de las sentencias de casaci\u00f3n de la honorable Corte Suprema de Justicia, en virtud del control de legalidad que le corresponde. &nbsp; &nbsp;<\/p>\n<p>En principio, podr\u00eda estimarse que cuando el art\u00edculo 31 se refiere &nbsp;al superior en ejercicio del recurso de apelaci\u00f3n est\u00e1 limitando la garant\u00eda constitucional de la reformatio in peius a la segunda instancia y excluyendo, por tanto, las sentencias de casaci\u00f3n. Tal ser\u00eda la conclusi\u00f3n de interpretar el requisito constitutivo de la interdicci\u00f3n, &#8220;apelante \u00fanico&#8221;, en sentido literal y referible \u00fanicamente al recurso de apelaci\u00f3n, sin que su aplicaci\u00f3n pudiera hacerse efectiva en el campo de la casaci\u00f3n. Sin embargo, el principio de efectividad de los principios, derechos y deberes consagrados en la Constituci\u00f3n, que constituye un fin esencial del Estado (CP art. 2), impone otra conclusi\u00f3n. Cuando la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, profiere una sentencia sustitutiva de la decisi\u00f3n casada, act\u00faa como Tribunal de instancia para todos los efectos y se convierte en el Juez &#8220;Superior&#8221; al cual alude el art\u00edculo 31 de la Constituci\u00f3n Pol\u00edtica. En dicho sentido, la Sala de Casaci\u00f3n Penal est\u00e1 plenamente vinculada a la garant\u00eda constitucional de la reformatio in peius, quedando obligada a verificar las circunstancias concretas &#8211; partes apelantes, car\u00e1cter y naturaleza de las pretensiones &#8211; a fin de determinar el quantum de la condena y dejar a salvo de esta forma los derechos fundamentales del procesado. &nbsp;<\/p>\n<p>Lo anterior no significa desvirtuar la funci\u00f3n especial\u00edsima del control de legalidad sobre todo el proceso ejercida por la Sala de Casaci\u00f3n Penal de&nbsp; &nbsp;<\/p>\n<p>la Corte Suprema de Justicia, como Tribunal de casaci\u00f3n, sino precisar la aplicaci\u00f3n de las reglas y principios que rigen la estimaci\u00f3n de la pena a imponer cuando se act\u00faa como juez o tribunal de instancia. &nbsp;<\/p>\n<p>En el caso sub-lite, la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, luego de casar la sentencia recurrida, conden\u00f3, en sentencia sustitutiva de la sentencia absolutoria del Tribunal Superior del Distrito Judicial de Santaf\u00e9 de Bogot\u00e1, al procesado MOISES &nbsp;TUATY ALEXANDER, a la pena principal de cuatro a\u00f1os y dos meses de prisi\u00f3n y al pago de cuatro millones trescientos treinta y ocho mil trescientos nueve pesos con setenta y dos centavos, a pesar de que el Juzgado Cuarto Penal del Circuito lo hab\u00eda condenado a la pena de dieciocho meses de prisi\u00f3n y al pago de un mill\u00f3n trescientos treinta y ocho mil trescientos nueve pesos con setenta y dos centavos, ostentando este \u00faltimo el car\u00e1cter de apelante \u00fanico de la condena penal, mientras que la parte civil hab\u00eda circunscrito su pretensi\u00f3n impugnativa a la mera inclusi\u00f3n de los perjuicios morales derivados de la infracci\u00f3n penal. As\u00ed las cosas, la reformatio in peius operaba plenamente en materia de la sanci\u00f3n penal impuesta por el juez de primera instancia, no aconteciendo lo mismo para el caso de los perjuicios materiales y morales, aspectos respecto de los cuales la Sala de Casaci\u00f3n Penal no estaba limitada en virtud del recurso interpuesto por la parte civil. En consecuencia, analizados los hechos y siendo manifiesta la vulneraci\u00f3n de la garant\u00eda fundamental del art\u00edculo 31 de la Constituci\u00f3n, as\u00ed como de los derechos fundamentales de defensa y debido proceso, esta Sala proceder\u00e1 a revocar la sentencia revisada y conceder la tutela solicitada. &nbsp;<\/p>\n<p>Vulneraci\u00f3n de derechos fundamentales y acci\u00f3n de tutela contra sentencias &nbsp;<\/p>\n<p>14. La Sala Plena de la Corte Suprema de Justicia en la sentencia aqu\u00ed revisada no entr\u00f3 a fallar de fondo sobre la posible vulneraci\u00f3n de los derechos fundamentales aducida por el accionante de tutela, por considerar que carec\u00eda de competencia para ello. &nbsp;<\/p>\n<p>La Corte Constitucional, en esta ocasi\u00f3n, prohija la tesis sostenida en la sentencia de esta misma Sala del 12 de mayo de 1992, en la cual se examin\u00f3 con suficiente extensi\u00f3n y detalle la procedencia de la acci\u00f3n de tutela con respecto a sentencias violatorias de derechos constitucionales fundamentales, as\u00ed como la competencia de las diferentes salas de la Corte Suprema de Justicia para conocer de dichas acciones. &nbsp;<\/p>\n<p>La regulaci\u00f3n legal de la acci\u00f3n y una interpretaci\u00f3n estricta de la misma &#8211; justamente con el fin de velar por su mantenimiento-, permiten se\u00f1alar los siguientes requisitos necesarios para que proceda contra sentencias y dem\u00e1s providencias que pongan t\u00e9rmino a un proceso: &nbsp; &nbsp;<\/p>\n<p>a) Que exista una vulneraci\u00f3n o amenaza contra un derecho fundamental, en este caso, de aquellos que tienen por destinatario al Juez en su funci\u00f3n de interpretar y aplicar el derecho y que generan obligaciones judiciales de hacer o no hacer cuyo incumplimiento no puede carecer de v\u00edas de exigibilidad en un Estado Social de Derecho, por ejemplo, los denominados derechos al debido proceso sustancial o derechos fundamentales procesales, que comprenden, entre otros, la prohibici\u00f3n de la pena de muerte, el derecho a la integridad personal y los derechos consagrados en los art\u00edculos 29, 31, 33 y 346 de la Constituci\u00f3n Pol\u00edtica, excluy\u00e9ndose como es obvio los que tienen garant\u00edas propias como el Habeas Corpus (art\u00edculo 30). &nbsp;<\/p>\n<p>Estos derechos, particularmente los derechos fundamentales procesales, sino tuvieran la coacci\u00f3n que les otorga la tutela, se volver\u00edan pr\u00e1cticamente in\u00fatiles, y degenerar\u00edan en vacuas declamaciones, quedando desprovistos de un mecanismo jur\u00eddico esencial para su eficaz operancia, como reglas sustanciales de derecho y garant\u00edas b\u00e1sicas del sistema judicial. Por ello, si el art\u00edculo 86 de la Constituci\u00f3n hubiera sustra\u00eddo de la acci\u00f3n de tutela la sentencias de los jueces, en todo caso se habr\u00eda hecho necesario aplicarla, por entra\u00f1ar tales derechos garant\u00edas inherentes a la persona humana (art\u00edculo 94 Constituci\u00f3n Pol\u00edtica). &nbsp;<\/p>\n<p>La eficacia de los derechos fundamentales procesales, es tan cara a la humanidad que incluso tiene protecci\u00f3n internacional, en el evento de que el Ordenamiento Jur\u00eddico Nacional no la consagre. Basta se\u00f1alar que este efecto podr\u00eda obtenerse recurriendo al ejercicio de una acci\u00f3n concreta ante la Comisi\u00f3n Interamericana de Derechos Humanos (art\u00edculo 44 de la Convenci\u00f3n Americana de Derechos Humanos), por solicitud de cualquier persona o entidad no gubernamental, lo que dar\u00eda lugar a un procedimiento con la intervenci\u00f3n de la Corte Interamericana de Derechos Humanos (art\u00edculo 63 de la Convenci\u00f3n Americana de Derechos Humanos). &nbsp;<\/p>\n<p>b) Que la vulneraci\u00f3n o amenaza se produzca por y en la parte resolutiva de la sentencia o providencia, sin que exista otro mecanismo id\u00f3neo para reclamar la prevalencia del derecho vulnerado o amenazado. &nbsp;<\/p>\n<p>c) Que la violaci\u00f3n o amenaza pueda ser deducida de manera clara, directa, manifiesta, ostensible y evidente. &nbsp;<\/p>\n<p>d) Por v\u00eda negativa, queda excluida la posibilidad de practicar pruebas a fin de determinar el contenido y alcance de la presunta violaci\u00f3n o amenaza de un derecho fundamental. &nbsp;<\/p>\n<p>e) Que no exista otro mecanismo id\u00f3neo de defensa judicial, diferente de la acci\u00f3n de tutela, para reclamar la protecci\u00f3n del derecho vulnerado o amenazado, del cual pueda predicarse la misma inmediatez y eficacia para la protecci\u00f3n efectiva, id\u00f3nea y real del derecho conculcado.&nbsp; &nbsp;<\/p>\n<p>A prop\u00f3sito de esta \u00faltima exigencia es preciso advertir que la denominada &#8220;acci\u00f3n de revisi\u00f3n&#8221; de la Corte Suprema de Justicia, regulada en el art\u00edculo 232 numeral cuarto del C\u00f3digo de Procedimiento Penal, establecida para revisar sentencias cuando se comprueben casos de prevaricato por parte del fallador, no es un medio alternativo de defensa judicial en este caso. En efecto, este tipo de procesos exige el tr\u00e1mite previo de un proceso penal que condiciona el inicio de la revisi\u00f3n. Una vez haya condena en firme en el proceso penal se podr\u00e1, s\u00f3lo entonces, iniciar la revisi\u00f3n, perdi\u00e9ndose as\u00ed no s\u00f3lo la existencia de la inmediatez de la protecci\u00f3n del derecho constitucional -de que trata el art\u00edculo 86-, sino que ser\u00eda contingente la protecci\u00f3n del mismo. Por otra parte, si el fallador que ha violado el derecho ostenta la investidura de Magistrado de las altas Corporaciones, se requiere, adem\u00e1s, espec\u00edfica acusaci\u00f3n por parte de la C\u00e1mara de Representantes ante el Senado, el cual luego remite el acusado a la Sala Penal de la Corte Suprema de Justicia, de conformidad con los art\u00edculos 174 y 175.3 de la Constituci\u00f3n. Esta hip\u00f3tesis, por su inidoneidad absoluta para proteger el derecho constitucional fundamental, debe ser desechada como mecanismo alternativo de defensa judicial. &nbsp;<\/p>\n<p>Vulneraci\u00f3n manifiesta de derechos fundamentales y justificaci\u00f3n del fallo de revisi\u00f3n&nbsp; &nbsp;<\/p>\n<p>15. Verificada la violaci\u00f3n de los derechos fundamentales mencionados, por parte de la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, lo que se efect\u00fao mediante sentencia suya del 9 de octubre de 1991, reca\u00edda en el proceso penal seguido contra el se\u00f1or MOISES TUATY ALEXANDER por el delito de tentativa de estafa, procede revocar la sentencia denegatoria de la tutela emanada de la Sala Plena y que es materia de revisi\u00f3n. El car\u00e1cter manifiesto de la vulneraci\u00f3n, unido a la \u00edndole inhibitoria de la sentencia de tutela dictada por la Sala Plena de la Corte Suprema de Justicia, lleva a esta Corporaci\u00f3n a disponer la protecci\u00f3n inmediata de los derechos constitucionales fundamentales conculcados, para lo cual se revocar\u00e1 parcialmente la sentencia de la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, de fecha ya referida.&nbsp; &nbsp;<\/p>\n<p>DECISION &nbsp;<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Segunda de Revisi\u00f3n &nbsp;de la Corte Constitucional,&nbsp; &nbsp;<\/p>\n<p>R E S U E L V E &nbsp;<\/p>\n<p>PRIMERO.- REVOCAR la sentencia del &nbsp;30 de enero de 1992, proferida por la Sala Plena de la Corte Suprema de Justicia, mediante la cual se deneg\u00f3 la tutela solicitada por el se\u00f1or MOISES TUATY ALEXANDER. &nbsp;<\/p>\n<p>SEGUNDO.- CONCEDER la tutela solicitada por el se\u00f1or MOISES TUATY ALEXANDER y, con el objeto de dar protecci\u00f3n inmediata a sus derechos fundamentales de defensa y al debido proceso, REVOCAR parcialmente la sentencia de la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, proferida el nueve (9) de octubre de 1991, por ser violatoria de los art\u00edculos 29 y 31 de la Constituci\u00f3n, en lo relativo a la agravaci\u00f3n de la pena de privaci\u00f3n de la libertad impuesta por el Juzgado de primera instancia. En consecuencia, la mencionada condena queda reducida hasta la m\u00e1xima privaci\u00f3n de la libertad ordenada por el Juez Cuarto Penal del Circuito de Santaf\u00e9 de Bogot\u00e1, es decir, dieciocho (18) &nbsp;meses de prisi\u00f3n.&nbsp; &nbsp;<\/p>\n<p>TERCERO.- LIBRESE comunicaci\u00f3n a la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, con miras a que se surta la notificaci\u00f3n de esta providencia, seg\u00fan lo establecido en el art\u00edculo 36 del Decreto 2591 de 1991, y rem\u00edtase copia de la providencia al Juzgado Cuarto Penal del Circuito de Santaf\u00e9 de Bogot\u00e1 a fin de que obre en el proceso penal respectivo. &nbsp;<\/p>\n<p>C\u00f3piese, comun\u00edquese, c\u00famplase e ins\u00e9rtese en la Gaceta de la Corte Constitucional. &nbsp;<\/p>\n<p>EDUARDO CIFUENTES MU\u00d1OZ &nbsp;<\/p>\n<p>Magistrado Ponente &nbsp;<\/p>\n<p>JOSE GREGORIO HERNANDEZ GALINDO &nbsp;<\/p>\n<p>Magistrado &nbsp; &nbsp; &nbsp;<\/p>\n<p>-Salvamento de voto- &nbsp;<\/p>\n<p>ALEJANDRO MARTINEZ CABALLERO &nbsp;<\/p>\n<p>&nbsp; &nbsp;Magistrado &nbsp; &nbsp;<\/p>\n<p>(Sentencia aprobada por la Sala Segunda de Revisi\u00f3n, en la ciudad de Santaf\u00e9 de Bogot\u00e1, D.C., a los veintinueve (29) d\u00edas del mes de julio de mil novecientos noventa y dos ). &nbsp;<\/p>\n<p>Salvamento de voto a la Sentencia No. T-474 &nbsp;<\/p>\n<p>ACCION DE TUTELA CONTRA SENTENCIAS-Improcedencia (Salvamento de voto) &nbsp;<\/p>\n<p>A la luz del mandato contenido en el art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica, no era procedente la acci\u00f3n de tutela y, por tanto, ha debido confirmarse la sentencia &nbsp;proferida por la Sala Plena de la Corte Suprema de Justicia. &nbsp;<\/p>\n<p>Ref.: Sentencia T-474 &nbsp;<\/p>\n<p>Actor MOISES TUATY ALEXANDER &nbsp;<\/p>\n<p>Magistrados Ponentes: &nbsp;<\/p>\n<p>Dr. EDUARDO CIFUENTES MU\u00d1OZ &nbsp;<\/p>\n<p>Dr. ALEJANDRO MARTINEZ CABALLERO &nbsp;<\/p>\n<p>Santaf\u00e9 de Bogot\u00e1,D.C., veintinueve (29) de julio &nbsp;de mil novecientos noventa y dos (1992). &nbsp;<\/p>\n<p>Me he apartado de la decisi\u00f3n mayoritaria adoptada mediante el fallo en referencia por estimar que en el caso examinado, a la luz del mandato contenido en el art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica, no era procedente la acci\u00f3n de tutela y, por tanto, ha debido confirmarse la sentencia del 30 de enero de 1992, proferida por la Sala Plena de la Corte Suprema de Justicia. &nbsp;<\/p>\n<p>No estimo necesario extenderme en consideraciones sobre el motivo de mi disentimiento, pues ellas est\u00e1n consignadas en su parte fundamental (improcedencia de la acci\u00f3n de tutela contra providencias judiciales que han hecho tr\u00e1nsito a cosa juzgada) en salvamento de voto de fecha 12 de mayo de 1992, relativo a la sentencia No. 6 Sala de Revisi\u00f3n No. 2 (Magistrado Ponente: Doctor Eduardo Cifuentes Mu\u00f1oz). &nbsp;<\/p>\n<p>JOSE GREGORIO HERNANDEZ GALINDO &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp;<\/p>\n<p>1 Corte Suprema de Justicia. Sala de Casaci\u00f3n Penal . Sentencia del &nbsp;25 de octubre de 1989. Magistrado Ponente: Dr. Edgar Saavedra Rojas &nbsp;<\/p>\n<p>2 Corte Suprema de Justicia. &nbsp;Sala de Casaci\u00f3n Penal . Sentencia del 9 de noviembre de 1989. Magistrado Ponente: Dr. Edgar Saavedra Rojas &nbsp;<\/p>\n<p>3 Corte Suprema de Justicia. &nbsp;Sala de Casaci\u00f3n Penal . Sentencia del 23 de noviembre de 1989. Magistrado Ponente: Dr. &nbsp;Gustavo G\u00f3mez Vel\u00e1zquez. &nbsp;<\/p>\n<p>4 Tom\u00e1s y Valiente, Francisco. &#8220;In dubio pro reo&#8221;, libre apreciaci\u00f3n de la prueba y presunci\u00f3n de inocencia. Revista Espa\u00f1ola de Derecho Constitucional. A\u00f1o 7. Num.20. Mayo-Agosto de 1987 p\u00e1g. 21. &nbsp;<\/p>\n<p>5 Roxin\/Arzt\/Tiedemann: Introducci\u00f3n al Derecho Penal y al Derecho Penal Procesal. Ed. Ariel, Barcelona, 1989, p\u00e1g. 226.&nbsp; &nbsp;<\/p>\n<p>6 Cfr. Corte Suprema de Justicia. Sentencia del 27 de marzo de 1989. MP Fabio Mor\u00f3n D\u00edaz, en la cual se declar\u00f3 inexequible el Decreto 2490 de 1988, que establec\u00eda la cadena perpetua, justamente con base en la idea seg\u00fan la cual un juez no podr\u00eda desconocer las garant\u00edas m\u00ednimas constitucionales. &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>T-474-92 &nbsp; &nbsp; Sentencia No. T-474\/92 &nbsp; DEBIDO PROCESO\/RESOLUCION DE ACUSACION-Circunstancias agravantes &nbsp; La doctrina que no reconoce la obligaci\u00f3n &#8211; cuya violaci\u00f3n entra\u00f1a nulidad constitucional &#8211; de mencionar expresamente en todos los casos las circunstancias espec\u00edficas de agravaci\u00f3n punitiva en el pliego de cargos, no se ajusta a las previsiones de la Constituci\u00f3n. En [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-142","post","type-post","status-publish","format-standard","hentry","category-tutelas"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=142"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/142\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}