{"id":14373,"date":"2024-06-05T17:34:56","date_gmt":"2024-06-05T17:34:56","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/06\/05\/t-184-07\/"},"modified":"2024-06-05T17:34:56","modified_gmt":"2024-06-05T17:34:56","slug":"t-184-07","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-184-07\/","title":{"rendered":"T-184-07"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia T-184\/07 \u00a0<\/p>\n<p>ACCION DE TUTELA TEMERARIA-Elementos para su configuraci\u00f3n \u00a0<\/p>\n<p>ACCION DE TUTELA-Subsidiariedad\/ACCION DE TUTELA-Improcedencia para ordenar reconocimiento de pensiones \u00a0<\/p>\n<p>ACCION DE TUTELA-Procedencia excepcional para ordenar reconocimiento de pensiones\u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA-Inexistencia de temeridad para el caso \u00a0<\/p>\n<p>ACCION DE TUTELA-Improcedencia por no demostraci\u00f3n de perjuicio irremediable ni vulneraci\u00f3n de derechos fundamentales \u00a0<\/p>\n<p>MEDIO DE DEFENSA JUDICIAL-Reconocimiento pensi\u00f3n de sobrevivientes \u00a0<\/p>\n<p>Referencia: expediente T-1496152 \u00a0<\/p>\n<p>Acci\u00f3n de tutela instaurada por Andrea Paola Monta\u00f1ez Ayala y otros contra el Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander. \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>Dr. JAIME ARAUJO RENTER\u00cdA \u00a0<\/p>\n<p>Bogot\u00e1, D., \u00a0quince (15) de marzo de dos mil siete (2007). \u00a0<\/p>\n<p>La Sala Primera de Revisi\u00f3n de la Corte Constitucional integrada por los Magistrados MANUEL JOS\u00c9 CEPEDA ESPINOSA, JAIME C\u00d3RDOBA TRIVI\u00d1O Y JAIME ARA\u00daJO RENTER\u00cdA, en ejercicio de sus competencias constitucionales y legales, espec\u00edficamente las previstas en los art\u00edculos 86 y 241 numeral 9 de la Constituci\u00f3n Pol\u00edtica y en el Decreto 2591 de 1991, profiere la siguiente: \u00a0<\/p>\n<p>SENTENCIA \u00a0<\/p>\n<p>Dentro del proceso de revisi\u00f3n del fallo dictado por el Juzgado Segundo de Familia de Bucaramanga que resolvi\u00f3 la acci\u00f3n de tutela promovida por Andrea Paola Monta\u00f1ez Ayala y Aureliano Monta\u00f1ez Pinz\u00f3n, quien act\u00faa en nombre propio y en representaci\u00f3n de la menor \u00c1ngela Mar\u00eda Monta\u00f1ez Ayala, contra el Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. ANTECEDENTES \u00a0 \u00a0<\/p>\n<p>El 24 de agosto de 2006, los ciudadanos Andrea Paola Monta\u00f1ez Ayala y Aureliano Monta\u00f1ez Pinz\u00f3n, quien act\u00faa en nombre propio y en representaci\u00f3n de la menor \u00c1ngela Mar\u00eda Monta\u00f1ez Ayala, interpusieron acci\u00f3n de tutela ante el Juzgado Segundo de Familia de Bucaramanga, contra el Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander, por considerar vulnerados sus derechos fundamentales a la vida en condiciones dignas y al m\u00ednimo vital. Fundamentaron su acci\u00f3n en los siguientes hechos y consideraciones: \u00a0<\/p>\n<p>1. Hechos:\u00a0 \u00a0<\/p>\n<p>1.1 Los accionantes afirman que su madre y c\u00f3nyuge, Ana Consuelo Ayala Vergara, falleci\u00f3 el d\u00eda 29 de diciembre de 2000 como consecuencia de una enfermedad de origen no profesional.\u00a0 \u00a0<\/p>\n<p>1.2 Manifiestan que la Se\u00f1ora Ayala Vergara, en virtud de su vinculaci\u00f3n laboral como Directora Administrativa de la Sociedad Ayala Vergara Ltda., estuvo afiliada al Sistema de Seguridad en Pensiones y en tal condici\u00f3n, cotiz\u00f3 al Instituto de Seguros Sociales por un t\u00e9rmino aproximado de 18 a\u00f1os hasta el d\u00eda de su muerte. \u00a0<\/p>\n<p>1.3 Indican que en comunicaci\u00f3n presentada el d\u00eda 2 de julio de 2003 ante el Instituto de Seguros Sociales, solicitaron el reconocimiento de la pensi\u00f3n de sobrevivientes por la muerte de la Se\u00f1ora Ayala Vergara.\u00a0 \u00a0<\/p>\n<p>1.4 Sostienen que mediante la Resoluci\u00f3n No 000967 del d\u00eda 20 de febrero de 2004, el Instituto de Seguros Sociales deneg\u00f3 la solicitud presentada. Para argumentar su decisi\u00f3n, el Instituto adujo que la Se\u00f1ora Ayala Vergara al momento de su muerte, no cumpl\u00eda con los requisitos establecidos en el art\u00edculo 46 de la ley 100 de 1993. En \u00e9ste sentido, el Instituto se\u00f1al\u00f3 que para el d\u00eda 29 de diciembre de 2002, la asegurada no se encontraba cotizando al sistema de pensiones y que ninguna de las 887 semanas cotizadas durante el per\u00edodo de su afiliaci\u00f3n, se hab\u00eda efectuado el a\u00f1o inmediatamente anterior al momento de su deceso. \u00a0<\/p>\n<p>As\u00ed mismo, la Entidad estim\u00f3 que conforme a lo dispuesto en el art\u00edculo 36 de la ley 90 de 1946, los accionantes no ten\u00edan derecho al reconocimiento de la indemnizaci\u00f3n sustitutiva de la pensi\u00f3n de vejez, por cuanto la acci\u00f3n judicial se encontraba prescrita. \u00a0 \u00a0<\/p>\n<p>1.5 Como consecuencia de la negativa de la Entidad, los accionantes interpusieron los recursos de \u00a0reposici\u00f3n y en subsidio el de apelaci\u00f3n contra la Resoluci\u00f3n No 000967 de 2004. En la sustentaci\u00f3n de dichos recursos, manifestaron que a diferencia de lo se\u00f1alado por el Instituto en la Resoluci\u00f3n en comento, la Se\u00f1ora Ayala Vergara si cumpl\u00eda con los requisitos del art\u00edculo 46 de la ley 100 de 1993 pues al momento de su muerte, ten\u00eda 939 semanas cotizadas, de las cuales 51 se hab\u00edan efectuado durante el a\u00f1o anterior a su fallecimiento.\u00a0 \u00a0<\/p>\n<p>1.6 Dado que la Entidad no se pronunci\u00f3 oportunamente sobre los recursos interpuestos contra la Resoluci\u00f3n No 000967, se\u00f1alan que los d\u00edas 15 de junio de 2005 y \u00a013 de septiembre del mismo a\u00f1o, presentaron solicitudes ante el Instituto a fin de que \u00e9ste emitiera una decisi\u00f3n de fondo sobre tales recursos y que para el efecto, accediera al reconocimiento de la pensi\u00f3n de sobrevivientes. \u00a0<\/p>\n<p>1.7 Como consecuencia de lo anterior, el d\u00eda 14 de marzo de 2006 los accionantes presentaron una acci\u00f3n de tutela ante el Juzgado D\u00e9cimo Civil del Circuito de Bucaramanga por considerar vulnerados sus derechos fundamentales de petici\u00f3n, seguridad social y m\u00ednimo vital. En el escrito de tutela, los accionantes solicitaron al juez de instancia que ordenara al Instituto de Seguros Sociales decidir los recursos interpuestos y otorgar el reconocimiento de la pensi\u00f3n de sobrevivientes reclamada. \u00a0<\/p>\n<p>1.8 En sentencia del d\u00eda 28 de marzo de 2006, el Juzgado D\u00e9cimo Civil del Circuito de Bucaramanga concedi\u00f3 el amparo invocado por estimar que el Instituto de Seguros Sociales, vulner\u00f3 el derecho fundamental de petici\u00f3n de los accionantes. As\u00ed, puesto que durante el tr\u00e1mite de la acci\u00f3n de tutela la Entidad decidi\u00f3 el recurso de reposici\u00f3n, el juez de tutela orden\u00f3 que el Instituto se pronunciara sobre el recurso de apelaci\u00f3n interpuesto. \u00a0<\/p>\n<p>Aunque en la parte resolutiva de la Sentencia el juez de tutela no se pronunci\u00f3 al respecto, en las Consideraciones de \u00e9sta, indic\u00f3 que la acci\u00f3n de tutela era improcedente para ordenar al Instituto de Seguros Sociales el reconocimiento de la pensi\u00f3n de sobrevivientes. En \u00e9ste sentido afirm\u00f3: \u201cAhora, lo que no puede hacer \u00e9ste Despacho es promover el reconocimiento de una pensi\u00f3n de sobrevivientes, como pretende la parte accionante; ello por cuanto dicho asunto se escapa de la \u00f3rbita del Juez de tutela, al no contar con los elementos de juicio suficientes para determinar dicho asunto, para el cual est\u00e1 radicada la competencia en la jurisdicci\u00f3n ordinaria laboral. Por ello, la orden judicial se limitar\u00e1 a proteger el derecho de petici\u00f3n, conminando a la accionada para que resuelva el respectivo recurso de apelaci\u00f3n.\u201d\u00a0 \u00a0<\/p>\n<p>1.9 En cumplimiento de la sentencia de tutela del Juzgado D\u00e9cimo Civil del Circuito de Bucaramanga, el d\u00eda 24 de abril de 2006 el Instituto de Seguros Sociales emiti\u00f3 la Resoluci\u00f3n No 0364, mediante la cual resolvi\u00f3 el recurso de apelaci\u00f3n y confirm\u00f3 la decisi\u00f3n de denegar el reconocimiento de la pensi\u00f3n de sobrevivientes a los accionantes.\u00a0 \u00a0<\/p>\n<p>Al respecto, indic\u00f3 que con posterioridad al fallecimiento de la Sra. Ayala Vergara, la Sociedad Ayala Vergara Ltda. cancel\u00f3 al Instituto los aportes atrasados. Explic\u00f3 que de acuerdo con lo dispuesto en el art\u00edculo 53 del Decreto 1406 de 1999, los aportes realizados con posterioridad a la muerte del asegurado, no pueden ser tenidos en cuenta para efectos de otorgar el reconocimiento de la prestaci\u00f3n econ\u00f3mica solicitada. \u00a0<\/p>\n<p>Concluye el Instituto, que como consecuencia de que la Se\u00f1ora Ayala Vergara no se encontraba cotizando al sistema de pensiones al momento de su muerte, y que no hab\u00eda efectuado aportes durante las 26 semanas inmediatamente anteriores a su fallecimiento, no era posible otorgar el reconocimiento de la pensi\u00f3n de sobrevivientes exigida por los peticionarios.\u00a0 \u00a0<\/p>\n<p>1.10 Los accionantes agregan que la negativa del Instituto de Seguros Sociales en el reconocimiento de la pensi\u00f3n de sobrevivientes, as\u00ed como la situaci\u00f3n de inestabilidad laboral del Se\u00f1or Aureliano Monta\u00f1ez Pinz\u00f3n, han puesto a la menor de 16 a\u00f1os \u00c1ngela Mar\u00eda Monta\u00f1ez Ayala \u201cen condiciones sicol\u00f3gicas (sic) bastante dif\u00edciles\u201d; y a todo el grupo familiar \u201cen estado de indefensi\u00f3n\u201d, razones por las cuales, para garantizar su sustento econ\u00f3mico, han tenido que acudir a la ayuda de sus familiares. \u00a0<\/p>\n<p>1.11 En su criterio, la decisi\u00f3n del Instituto de Seguros Sociales vulnera sus derechos fundamentales a la vida en condiciones dignas y al m\u00ednimo vital, pues la prestaci\u00f3n econ\u00f3mica exigida representa una importante fuente de ingreso que les permitir\u00eda satisfacer adecuadamente sus necesidades b\u00e1sicas y mejorar su calidad de vida.\u00a0 \u00a0<\/p>\n<p>Adicionalmente, afirman que &#8211; tal y como lo indican la jurisprudencia de la Corte Constitucional y la legislaci\u00f3n que regula la materia &#8211; la omisi\u00f3n del Instituto de Seguros Sociales en adelantar las acciones de cobro de los aportes dejados de pagar por parte del empleador, no puede derivar en la negativa del reconocimiento de la pensi\u00f3n de sobrevivientes solicitada; y en consecuencia, en la vulneraci\u00f3n de sus derechos en calidad de causahabientes de la Se\u00f1ora Ayala Vergara.\u00a0 \u00a0<\/p>\n<p>2. Solicitud de tutela\u00a0 \u00a0<\/p>\n<p>2.1 Por lo anterior, el d\u00eda 24 de agosto de 2006, los ciudadanos Andrea Paola Monta\u00f1ez Ayala y Aureliano Monta\u00f1ez Pinz\u00f3n, quien act\u00faa en nombre propio y en representaci\u00f3n de la menor \u00c1ngela Mar\u00eda Monta\u00f1ez Ayala, interpusieron acci\u00f3n de tutela ante el Juzgado Segundo de Familia de Bucaramanga contra el Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander, por considerar vulnerados sus derechos fundamentales a la vida en condiciones dignas y al m\u00ednimo vital. \u00a0<\/p>\n<p>2.2 Con fundamento en las consideraciones y hechos descritos anteriormente, \u00a0los accionantes solicitan que el juez de tutela ordene al Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander, efectuar el reconocimiento de la pensi\u00f3n de sobrevivientes reclamada, as\u00ed como su pago retroactivo desde la fecha en que se caus\u00f3 el derecho. \u00a0<\/p>\n<p>3. Tr\u00e1mite de instancia \u00a0<\/p>\n<p>3.1 La acci\u00f3n fue tramitada ante el Juzgado Segundo de Familia de Bucaramanga, el cual mediante auto del d\u00eda 25 de agosto de 2006 orden\u00f3 su notificaci\u00f3n al representante legal del Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander. Adicionalmente, dispuso que la Entidad accionada rindiera un informe sobre las razones por las cuales no ha efectuado el reconocimiento de la pensi\u00f3n de sobrevivientes solicitada por los accionantes.\u00a0 \u00a0<\/p>\n<p>3.2 En escrito dirigido al juez de tutela el d\u00eda 4 de septiembre de 2006, el Gerente (E) del Instituto de Seguros Sociales Seccional Santander, Medardo Faber Mej\u00eda Palomino, solicit\u00f3 al juez de tutela declarar la improcedencia del amparo invocado. \u00a0 \u00a0<\/p>\n<p>Para ello, sostuvo que los accionantes tienen a su disposici\u00f3n otros recursos y medios de defensa judicial para revocar las resoluciones No 000967 de 2004 y 0364 de 2006, mediante las cuales la Entidad resolvi\u00f3 las solicitudes y recursos interpuestos y deneg\u00f3 la solicitud de reconocimiento de la pensi\u00f3n de sobrevivientes exigida por sus presuntos beneficiarios.\u00a0 \u00a0<\/p>\n<p>3.3 En \u00e9ste sentido, el Gerente (E) del Instituto explic\u00f3 que la decisi\u00f3n de la Entidad se fundamenta en que la Se\u00f1ora Ayala Vergara no cumple los requisitos establecidos en los art\u00edculos 46 de la ley 100 de 1993 y 53 del Decreto 1406 de 1999. Esto por cuanto, al momento de su muerte, la Se\u00f1ora Ayala Vergara \u00a0no se encontraba cotizando al sistema de pensiones y no hab\u00eda realizado aportes durante el a\u00f1o inmediatamente anterior a la fecha de su deceso. Adicionalmente, en criterio del Instituto, los aportes realizados por parte de la Sociedad Ayala Vergara Ltda. con posterioridad a la muerte de su trabajadora, no pueden ser tenidos en cuenta para efectos de otorgar el reconocimiento de la pensi\u00f3n de sobrevivientes.\u00a0 \u00a0<\/p>\n<p>4. Pruebas relevantes que obran en el expediente. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Folio 19, cuaderno 2, copia de la Resoluci\u00f3n No 000967 de 2004 expedida por el Departamento de Pensiones del Instituto de Seguros Sociales Seccional Santander, mediante la cual deniega la pensi\u00f3n de sobrevivientes por la muerte de la asegurada Ana Consuelo Ayala Vergara, a favor de su c\u00f3nyuge Aureliano Monta\u00f1ez Pinz\u00f3n, y sus hijas \u00c1ngela Mar\u00eda Monta\u00f1ez Ayala, Anita Monta\u00f1ez Ayala y Andrea Paola Monta\u00f1ez Ayala. \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Folios 33 &#8211; 35, cuaderno 2, copia de la Resoluci\u00f3n No 004344 de 2004 expedida por el Departamento de Pensiones del Instituto de Seguros Sociales Seccional Santander, mediante la cual resolvi\u00f3 el recurso de reposici\u00f3n y concedi\u00f3 el recurso de apelaci\u00f3n contra la Resoluci\u00f3n No 000967 de 2004. \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Folios 20 &#8211; 22, cuaderno 2, copia de la Resoluci\u00f3n No 0364 de 2006, expedida por la Gerencia del Instituto de Seguros Sociales Seccional Santander, mediante la cual resolvi\u00f3 el recurso de apelaci\u00f3n interpuesto contra la Resoluci\u00f3n No 000967 de 2004. \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Folios 23 \u2013 26, cuaderno 2, copia de la sentencia del d\u00eda 28 de marzo de 2006 del Juzgado D\u00e9cimo Civil del Circuito de Bucaramanga, mediante la cual decidi\u00f3 la acci\u00f3n de tutela interpuesta por los accionantes el d\u00eda 14 de marzo de 2006. \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. LA SENTENCIA QUE SE REVISA \u00a0 \u00a0<\/p>\n<p>En sentencia \u00fanica de instancia del 6 de septiembre de 2006, el Juzgado Segundo de Familia declar\u00f3 improcedente la presente acci\u00f3n de tutela. Para ello, el Juzgado argument\u00f3 que en cumplimiento del numeral 1 del art\u00edculo 6 del Decreto 2591 de 1991, la presente acci\u00f3n de tutela es improcedente pues los accionantes tienen a su alcance otros medios y recursos de defensa judiciales para obtener el amparo de sus pretensiones.\u00a0 \u00a0<\/p>\n<p>Explic\u00f3 que de acuerdo con lo expresado por la Corte Constitucional \u201clas decisiones adoptadas por las entidades que legalmente han sido se\u00f1aladas por el legislador en cuanto a solicitudes de pensiones se refiere, son actos administrativos propios sobre los cuales no puede recaer la acci\u00f3n de tutela, pues ciertamente son \u00e9stas quienes tienen el deber legal de analizar la documentaci\u00f3n allegada y decidir sobre las mismas, como claramente ocurri\u00f3 en \u00e9ste caso.\u201d \u00a0<\/p>\n<p>El juez de instancia concluy\u00f3 que la presente acci\u00f3n es igualmente \u00a0improcedente porque no es competencia del juez de tutela ordenar el reconocimiento de una prestaci\u00f3n econ\u00f3mica. As\u00ed mismo, a su juicio, el amparo es improcedente porque los accionantes no lograron demostrar que a trav\u00e9s de la acci\u00f3n de tutela se busca evitar la ocurrencia de un perjuicio irremediable. \u00a0<\/p>\n<p>III. CONSIDERACIONES Y FUNDAMENTOS DE LA CORTE. \u00a0<\/p>\n<p>1. Competencia \u00a0<\/p>\n<p>De conformidad con lo establecido en los art\u00edculos 86 y 241-9 de la Constituci\u00f3n Pol\u00edtica y 31 a 36 del Decreto 2591 de 1991 y con la selecci\u00f3n y el reparto efectuados el 15 de Diciembre de 2006, esta Sala es competente para revisar la decisi\u00f3n judicial mencionada. \u00a0<\/p>\n<p>2. Problema Jur\u00eddico \u00a0<\/p>\n<p>2.1 De acuerdo con los hechos expuestos, en el presente caso corresponde a la Corte examinar el siguiente problema jur\u00eddico: \u00bf Es procedente la acci\u00f3n de tutela para obtener el reconocimiento de una pensi\u00f3n de sobrevivientes, por violaci\u00f3n de los derechos fundamentales de sus presuntos beneficiarios al m\u00ednimo vital y a la vida en condiciones dignas?. En caso afirmativo, \u00e9sta Sala estudiar\u00e1 el fondo del asunto, esto es, si debe ordenarse o no dicho reconocimiento. \u00a0<\/p>\n<p>Para dar soluci\u00f3n al problema jur\u00eddico planteado, \u00e9sta Sala deber\u00e1 pronunciarse sobre la regla general de improcedencia de la acci\u00f3n de tutela por incumplimiento del requisito de subsidiariedad. Particularmente, reiterar\u00e1 la regla jurisprudencial seg\u00fan la cual, la acci\u00f3n de tutela, en principio, es improcedente en los casos en que a trav\u00e9s de \u00e9sta, se pretende el reconocimiento definitivo de una prestaci\u00f3n econ\u00f3mica como la pensi\u00f3n de sobrevivientes.\u00a0 \u00a0<\/p>\n<p>2.2 Antes de abordar el problema jur\u00eddico del presente caso, \u00e9sta Sala estima necesario resaltar que conforme a los hechos descritos en el escrito de tutela, el d\u00eda 14 de marzo de 2006 los accionantes interpusieron una acci\u00f3n de tutela ante el Juzgado D\u00e9cimo Civil del Circuito de Bucaramanga contra el Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander, por considerar vulnerados sus derechos fundamentales de petici\u00f3n, vida en condiciones dignas y m\u00ednimo vital. \u00a0En \u00e9ste escrito de tutela, los accionantes solicitaron al juez de instancia ordenara a la Entidad que se pronunciara sobre los recursos interpuestos contra la Resoluci\u00f3n No 000967 de 2004, en el sentido de otorgar el reconocimiento de la pensi\u00f3n de sobrevivientes denegada por el Instituto mediante dicha Resoluci\u00f3n. \u00a0<\/p>\n<p>En primer lugar, dado que los hechos y pretensiones de la acci\u00f3n de tutela que fueron analizados por el Juzgado D\u00e9cimo Civil del Circuito de Bucaramanga en la sentencia de tutela del d\u00eda 28 de marzo de 2006, guardan similitud con los hechos y pretensiones que fueron considerados por el \u00a0Juzgado Segundo de Familia en el fallo de tutela que ahora es objeto de revisi\u00f3n de \u00e9sta Sala, \u00e9sta Corte determinar\u00e1 s\u00ed la presente solicitud de amparo resulta temeraria y en consecuencia debe ser decidida desfavorablemente.\u00a0 \u00a0<\/p>\n<p>2.3 Con base en lo anterior, y en el evento en que la presente acci\u00f3n de tutela no constituya una actuaci\u00f3n temeraria, \u00e9sta Sala de Revisi\u00f3n estimar\u00e1 si es procedente amparar el derecho fundamental de los accionantes a la vida en condiciones dignas y al m\u00ednimo vital, presuntamente vulnerados por el Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander como consecuencia de su decisi\u00f3n de negar el reconocimiento de la pensi\u00f3n de sobrevivientes \u00a0reclamada. \u00a0<\/p>\n<p>3. \u00a0Temeridad en la acci\u00f3n de tutela. Reiteraci\u00f3n de jurisprudencia. \u00a0<\/p>\n<p>3.1 \u00a0De conformidad con el art\u00edculo 38 del Decreto 2591 de 1991, \u201cPor el cual se reglamenta la acci\u00f3n de tutela consagrada en el art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica\u201d existe actuaci\u00f3n temeraria \u201cCuando sin motivo expresamente justificado la misma acci\u00f3n de tutela sea presentada por la misma persona o su representante ante varios jueces o tribunales (\u2026)\u201d, caso en el cual \u201c(\u2026) se rechazar\u00e1n o decidir\u00e1n desfavorablemente todas las solicitudes\u201d. \u00a0<\/p>\n<p>3.2 En \u00e9ste sentido, en reiteradas oportunidades,1 \u00e9sta Corte ha precisado que en principio, la existencia de una actuaci\u00f3n temeraria se deriva de la concurrencia de los siguientes elementos: \u00a0<\/p>\n<p>(i) Que las acciones de tutela hayan sido presentadas por el mismo accionante o su representante legal contra el mismo accionado;\u00a0 \u00a0<\/p>\n<p>(ii) Que las solicitudes de amparo se fundamenten en los mismos hechos o en la misma causa;\u00a0 \u00a0<\/p>\n<p>(iii) Que el accionante busque a trav\u00e9s de cada acci\u00f3n de tutela la protecci\u00f3n de las mismas pretensiones y derechos fundamentales; y\u00a0 \u00a0<\/p>\n<p>(iv) Que la interposici\u00f3n de la nueva acci\u00f3n de tutela carezca de justificaci\u00f3n suficiente, en violaci\u00f3n directa del principio de la buena fe y del adecuado ejercicio del derecho a la administraci\u00f3n de justicia.2 \u00a0<\/p>\n<p>3.3 As\u00ed mismo, \u00e9sta Corporaci\u00f3n ha manifestado que la sola concurrencia de los elementos indicados no da lugar a la configuraci\u00f3n de una actuaci\u00f3n temeraria, y por lo tanto, a la imposici\u00f3n de las sanciones previstas por la ley para castigarla.3 Esto por cuanto el juez de tutela est\u00e1 llamado a presumir la buena fe del accionante, y s\u00f3lo en el evento que \u00e9sta logre ser desvirtuada a partir de la constataci\u00f3n de la actuaci\u00f3n dolosa o ama\u00f1ada de quien solicita el amparo constitucional, proceder a la aplicaci\u00f3n de dichas sanciones.\u00a0 \u00a0<\/p>\n<p>Al respecto, en la sentencia T-706 de 2006, la Corte afirm\u00f3:\u00a0 \u00a0<\/p>\n<p>\u201cEn este orden de cosas, el juez constitucional no podr\u00e1 negar de plano la procedencia de una acci\u00f3n de tutela cuando observe que antes de la presentaci\u00f3n de la misma, el peticionario hab\u00eda presentado otra u otras demandas de caracter\u00edsticas similares, pues primero deber\u00e1, como lo ha se\u00f1alado esta Corporaci\u00f3n, realizar un an\u00e1lisis detallado de los hechos y del material probatorio que le permita descartar, en primer lugar, la presunta identidad de partes, pretensiones y hechos, y, en segundo lugar, la ausencia de buena fe y de justificaci\u00f3n en la interposici\u00f3n de las distintas acciones (\u2026)\u201d. \u00a0<\/p>\n<p>As\u00ed, bajo las circunstancias anteriores, dado que no existe temeridad en la presentaci\u00f3n de las nuevas acciones de tutela, el juez de instancia debe declarar la improcedencia de la acci\u00f3n y no, como lo dispone el art\u00edculo 38 del decreto 2591 de 1991, rechazar o decidir desfavorablemente todas las solicitudes.5 \u00a0<\/p>\n<p>4. Principio de subsidiariedad de la acci\u00f3n de tutela. Improcedencia de la acci\u00f3n de tutela para ordenar el reconocimiento de una pensi\u00f3n. Reiteraci\u00f3n de Jurisprudencia. \u00a0<\/p>\n<p>4.1 De acuerdo con el inciso 3 del art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica, la acci\u00f3n de tutela \u201csolo proceder\u00e1 cuando el afectado no disponga de otro medio de defensa judicial, salvo que aquella se utilice como mecanismo transitorio para evitar un perjuicio irremediable. As\u00ed mismo, el numeral 1 del art\u00edculo 6 del Decreto 2591 de 1991, dispone que la acci\u00f3n de tutela es improcedente en los casos en que el accionante tenga a su alcance otros recursos o medios de defensa judiciales para la protecci\u00f3n de sus derechos.\u00a0 \u00a0<\/p>\n<p>4.2 En \u00e9ste sentido, \u00e9sta Corporaci\u00f3n ha sostenido que la acci\u00f3n de tutela obedece al principio de subsidiariedad,6 es decir: (i) no constituye un mecanismo de defensa judicial alternativo o supletorio de los recursos o medios ordinarios previstos por el legislador para el amparo de un derecho; (ii) no puede ser empleada para revivir oportunidades procesales vencidas como consecuencia de la inactividad injustificada del interesado; y, (iii) no constituye un \u00faltimo medio judicial para alegar la vulneraci\u00f3n o afectaci\u00f3n de un derecho.\u00a0 \u00a0<\/p>\n<p>4.3 En efecto, conforme a su naturaleza constitucional, la acci\u00f3n de tutela es el mecanismo preferente de protecci\u00f3n de los derechos fundamentales, cuyo ejercicio, debe estar dirigido a obtener un amparo efectivo e inmediato frente a los actos u omisiones que los amenacen o vulneren. Es por ello que la acci\u00f3n de tutela no puede ser entendida como una instancia id\u00f3nea para tramitar y decidir conflictos de rango legal, pues con \u00e9ste prop\u00f3sito, el legislador dispuso los medios y recursos judiciales adecuados, as\u00ed como las autoridades y jueces competentes. \u00a0<\/p>\n<p>4.4 En desarrollo del principio de subsidiariedad, la jurisprudencia constitucional ha se\u00f1alado que en los casos en que el accionante tenga a su alcance otros medios o recursos de defensa judiciales, la acci\u00f3n de tutela proceder\u00e1 excepcionalmente en los siguientes eventos: \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>i. Los medios ordinarios de defensa judicial no son suficientemente id\u00f3neos y eficaces para proteger los derechos presuntamente conculcados;\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>i. A\u00fan cuando tales medios de defensa judicial sean id\u00f3neos, de no concederse la tutela como mecanismo transitorio de protecci\u00f3n, se producir\u00eda un perjuicio irremediable a los derechos fundamentales. \u00a0 \u00a0 \u00a0<\/p>\n<p>(iii) El accionante es un sujeto de especial protecci\u00f3n constitucional (personas de la tercera edad, personas discapacitadas, mujeres cabeza de familia, poblaci\u00f3n desplazada, ni\u00f1os y ni\u00f1as), y por lo tanto su situaci\u00f3n requiere de particular consideraci\u00f3n por parte del juez de tutela.7 \u00a0<\/p>\n<p>4.5 As\u00ed mismo, en virtud del principio de subsidiariedad, en reiteradas oportunidades \u00e9sta Corte ha se\u00f1alado que la acci\u00f3n de tutela es improcedente para ordenar el reconocimiento de derechos pensionales.8 Al respecto, la Corporaci\u00f3n ha indicado que ello es as\u00ed, porque la acci\u00f3n de tutela no es el medio procesal id\u00f3neo para tramitar y decidir las controversias suscitadas alrededor del reconocimiento de derechos de tal naturaleza.\u00a0 \u00a0<\/p>\n<p>En consecuencia, el juez de tutela no puede indicarle a una entidad encargada del reconocimiento de una pensi\u00f3n, el contenido, alcance y efectos de sus decisiones en \u00e9ste sentido. Por el contrario, su competencia se circunscribe a verificar que la entidad responsable, de respuesta oportuna y de fondo a las solicitudes presentadas por los presuntos beneficiarios del derecho pensional.9 \u00a0<\/p>\n<p>Ahora bien, la jurisdicci\u00f3n ordinaria y los recursos y mecanismos de defensa sujetos a su conocimiento, son los escenarios adecuados para la discusi\u00f3n y decisi\u00f3n de derechos litigiosos como el derecho a una pensi\u00f3n. Al respecto, en la sentencia T-182 de 2004 la Corte precis\u00f3:\u00a0 \u00a0<\/p>\n<p>\u201cLa definici\u00f3n de la titularidad y el reconocimiento de una pensi\u00f3n ante la administraci\u00f3n, constituye en principio un asunto ajeno al \u00e1mbito de la jurisdicci\u00f3n constitucional en sede de tutela, siendo competencia del juez de tutela la verificaci\u00f3n de los t\u00e9rminos establecidos legalmente para dar respuesta a los peticionarios, independientemente de su resultado, pues en aras de proteger el derecho de petici\u00f3n debe ordenar a la autoridad competente en cada caso dar una respuesta que resuelva de fondo lo solicitado.\u201d \u00a0<\/p>\n<p>5.6 Sin embargo, frente al reconocimiento de derechos pensionales, en determinados casos la Corte Constitucional ha admitido la procedencia excepcional de la acci\u00f3n de tutela. En la sentencia T-836 de 2006 la Corte precis\u00f3 las reglas jurisprudenciales en atenci\u00f3n a las cuales, excepcionalmente es procedente la acci\u00f3n de tutela para ordenar el reconocimiento de una pensi\u00f3n: \u00a0<\/p>\n<p>\u201cEsta Sala de Revisi\u00f3n se\u00f1ala que la procedencia de este recurso es excepcional y que, por tal motivo, se encuentra condicionada a precisos l\u00edmites sustanciales y probatorios. En primer lugar, debe estar acreditado el perjuicio irremediable que se producir\u00eda en el caso en que el juez de tutela no reconozca, as\u00ed sea de manera provisional, el derecho pensional. La \u00edntima relaci\u00f3n que guarda el reconocimiento de las mesadas pensionales con los derechos a la vida, al m\u00ednimo vital, al trabajo y a la salud demandan del juez de tutela la m\u00e1s esmerada atenci\u00f3n con el objetivo de establecer si en el caso concreto alguno de estos derechos se encuentra amenazado. \u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>\u201cIgualmente, el juez de tutela debe mostrarse especialmente atento a estas amenazas cuando los beneficiarios de este derecho sean sujetos de especial protecci\u00f3n, como miembros de la tercera edad, ni\u00f1os, poblaci\u00f3n desplazada y madres cabeza de familia, pues en estos casos la lesi\u00f3n a sus derechos fundamentales tiene un efecto particularmente severo en la medida en que estos sujetos se encuentran previamente en una especial condici\u00f3n de desamparo, la cual se hace mucho m\u00e1s gravosa ante el no reconocimiento del derecho pensional. \u00a0<\/p>\n<p>El excepcional reconocimiento del derecho pensional por v\u00eda de tutela se encuentra sometido, adicionalmente, a una \u00faltima condici\u00f3n de tipo probatorio, consistente en que en el expediente est\u00e9 acreditada la procedencia del derecho, a pesar de la cual la entidad encargada de responder no ha hecho el mencionado reconocimiento o simplemente no ha ofrecido respuesta alguna a la solicitud.\u00a0 \u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>El mencionado requisito probatorio pretende garantizar dos objetivos: en primer lugar, busca asegurar la eficacia de los derechos fundamentales del sujeto que a pesar de encontrarse en una grave situaci\u00f3n originada en el no reconocimiento de su derecho pensional, cuya procedencia est\u00e1 acreditada, no ha visto atendida su solicitud de acuerdo a la normatividad aplicable y a las condiciones f\u00e1cticas en las que apoya su petici\u00f3n. Y, en segundo lugar, este requisito traza un claro l\u00edmite a la actuaci\u00f3n del juez de tutela, quien s\u00f3lo puede acudir a esta actuaci\u00f3n excepcional en los precisos casos en los cuales est\u00e9 demostrada la procedencia del reconocimiento. \u00a0<\/p>\n<p>5.7 En s\u00edntesis, se puede indicar que en virtud del principio de subsidiariedad la acci\u00f3n de tutela es improcedente para ordenar el reconocimiento de una pensi\u00f3n. Sin embargo, de manera excepcional y como mecanismo transitorio, el juez de tutela puede ordenar el reconocimiento de dicha prestaci\u00f3n econ\u00f3mica, si : (i) existe certeza sobre la ocurrencia de un perjuicio irremediable a los derechos fundamentales si el reconocimiento de la pensi\u00f3n no se hace efectivo; (ii) se encuentra plenamente demostrada la afectaci\u00f3n de los derechos fundamentales al m\u00ednimo vital y a la vida digna del accionante o de su n\u00facleo familiar; (iii) los beneficiarios del derecho pensional son sujetos de especial protecci\u00f3n constitucional; y, (iv) cuando conforme a las pruebas allegadas al proceso, el juez de tutela determina que efectivamente, a pesar de que le asiste al accionante el derecho pensional que reclama, \u00e9ste fue negado de manera caprichosa o arbitraria.10 \u00a0<\/p>\n<p>5. Estudio del caso concreto.\u00a0 \u00a0<\/p>\n<p>De acuerdo con los hechos que fundamentan la presente acci\u00f3n de tutela, el d\u00eda 2 de julio de 2003 los accionantes solicitaron ante el Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander, el reconocimiento de la pensi\u00f3n de sobrevivientes por la muerte de su c\u00f3nyuge y madre, la Sra. Ana Consuelo Ayala Vergara. \u00a0<\/p>\n<p>Mediante la Resoluci\u00f3n No 000967, el Instituto neg\u00f3 la solicitud presentada. Para ello, el Instituto argument\u00f3 que la Sra. Ayala Vergara, al momento de su muerte, no cumpl\u00eda con los requisitos establecidos en los art\u00edculos 46 de la ley 100 de 1993 y 53 del Decreto 1406 de 1999. Es decir, a juicio de la Entidad, para la fecha de su fallecimiento, la Sra. Ayala no se encontraba cotizando al sistema de pensiones y no hab\u00eda efectuado aportes durante las 26 semanas inmediatamente anteriores a su deceso. \u00a0<\/p>\n<p>Como consecuencia de la negativa de la Entidad, los accionantes interpusieron los recursos de \u00a0reposici\u00f3n y en subsidio el de apelaci\u00f3n contra la Resoluci\u00f3n No 000967 de 2004. En la sustentaci\u00f3n de dichos recursos, manifestaron que a diferencia de lo se\u00f1alado por el Instituto en la Resoluci\u00f3n en comento, la Se\u00f1ora Ayala Vergara si cumpl\u00eda con los requisitos exigidos por la ley para obtener el reconocimiento de la prestaci\u00f3n reclamada.\u00a0 \u00a0<\/p>\n<p>Por su parte, el Instituto de Seguros Sociales no se pronunci\u00f3 oportunamente sobre los recursos interpuestos por los accionantes contra la Resoluci\u00f3n No 000967. Como consecuencia de lo anterior, el d\u00eda 14 de marzo de 2006 los accionantes presentaron una acci\u00f3n de tutela ante el Juzgado D\u00e9cimo Civil del Circuito de Bucaramanga contra el Instituto de Seguros Sociales por considerar vulnerados sus derechos fundamentales de petici\u00f3n, seguridad social y m\u00ednimo vital. En \u00e9ste sentido, los accionantes solicitaron al juez de tutela que ordenara a la Entidad accionada, decidir los recursos interpuestos y otorgar el reconocimiento de la pensi\u00f3n de sobrevivientes de su c\u00f3nyuge y madre. \u00a0<\/p>\n<p>En cumplimiento de la sentencia de tutela del Juzgado D\u00e9cimo Civil del Circuito de Bucaramanga, el Instituto de Seguros Sociales emiti\u00f3 la Resoluci\u00f3n No 0364 de 2006, mediante la cual resolvi\u00f3 el recurso de apelaci\u00f3n y confirm\u00f3 la decisi\u00f3n de denegar el reconocimiento de la pensi\u00f3n de sobrevivientes.\u00a0 \u00a0<\/p>\n<p>Con fundamento en la decisi\u00f3n de la Entidad de denegar el reconocimiento de la pensi\u00f3n de sobrevivientes, el d\u00eda 24 de agosto de 2006 los accionantes interpusieron una nueva acci\u00f3n de tutela ante el Juzgado Segundo de Familia de Bucaramanga por considerar que dicha decisi\u00f3n vulner\u00f3 sus derechos fundamentales a la vida en condiciones dignas y al m\u00ednimo vital.\u00a0 \u00a0<\/p>\n<p>Al respecto, \u00a0sostienen que la negativa del Instituto en el reconocimiento de la pensi\u00f3n de sobrevivientes de su c\u00f3nyuge y madre, los priva de una importante fuente de ingresos para la satisfacci\u00f3n de sus necesidades. As\u00ed mismo, afirman que la decisi\u00f3n desfavorable de la Entidad no es acertada, ya que al momento de su muerte, la Sra. Ayala Vergara cumpl\u00eda con todos los requisitos exigidos por la ley para acceder al reconocimiento de la pensi\u00f3n que ellos reclaman.\u00a0 \u00a0<\/p>\n<p>Por ello, los accionantes solicitaron al Juzgado Segundo de Familia de Bucaramanga \u00a0que ordenara al Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander, efectuar el reconocimiento de la pensi\u00f3n de sobrevivientes reclamada, as\u00ed como su pago retroactivo desde la fecha en que se caus\u00f3 el derecho. \u00a0<\/p>\n<p>En escrito dirigido al juez de tutela el d\u00eda 4 de septiembre de 2006, el Gerente (E) del Instituto de Seguros Sociales Seccional Santander, solicit\u00f3 al juez de tutela declarar la improcedencia del amparo invocado. En su criterio, los accionantes tienen a su disposici\u00f3n otros recursos y medios de defensa judicial, para revocar la decisi\u00f3n de denegar la solicitud de reconocimiento de la pensi\u00f3n de sobrevivientes.\u00a0 \u00a0<\/p>\n<p>En sentencia \u00fanica de instancia del d\u00eda 6 de septiembre de 2006, el Juzgado Segundo de Familia declar\u00f3 la improcedencia de la acci\u00f3n de tutela. Sostuvo que los accionantes cuentan con otros medios y recursos de defensa judiciales para atacar la decisi\u00f3n del Instituto. Adicionalmente, el juez de tutela indic\u00f3 que la acci\u00f3n de tutela no es el mecanismo id\u00f3neo para obtener el reconocimiento de una prestaci\u00f3n econ\u00f3mica como la pensi\u00f3n de sobrevivientes. \u00a0<\/p>\n<p>Ausencia de temeridad en el presente caso. \u00a0<\/p>\n<p>Indicadas las reglas jurisprudenciales en materia de temeridad en la acci\u00f3n de tutela, procede \u00e9sta Sala de Revisi\u00f3n a determinar si en el presente caso se configura una actuaci\u00f3n temeraria por parte de los accionantes. En el evento en que \u00e9sta quede desvirtuada, la Sala analizar\u00e1 la procedencia del amparo constitucional invocado.\u00a0 \u00a0<\/p>\n<p>Conforme a los hechos expuestos, en el presente caso queda demostrado que la acci\u00f3n de tutela presentada el d\u00eda 14 de marzo de 2006 y la acci\u00f3n de tutela presentada el d\u00eda 24 de agosto de 2006, guardan identidad de partes, esto es, fueron interpuestas por los mismos accionantes contra la misma entidad. \u00a0 \u00a0<\/p>\n<p>Sin embargo, como pasar\u00e1 a demostrarse, la presentaci\u00f3n de la acci\u00f3n de tutela presentada el d\u00eda 24 de agosto de 2006, no constituye una actuaci\u00f3n temeraria con relaci\u00f3n a la acci\u00f3n de tutela presentada el d\u00eda 14 de marzo de 2006. \u00a0<\/p>\n<p>En efecto, en la primera solicitud de tutela los accionantes solicitaron al juez que ordenara al Instituto de Seguros Sociales decidir los recursos interpuestos contra la Resoluci\u00f3n No 000967 de 2004 y otorgar el reconocimiento de la pensi\u00f3n de sobrevivientes. Sin embargo, en la parte resolutiva de la Sentencia el juez de tutela se pronunci\u00f3 sobre la primera pretensi\u00f3n pero no sobre la segunda. S\u00f3lo en \u00a0las Consideraciones de la providencia, indic\u00f3 que la acci\u00f3n de tutela era improcedente para ordenar al Instituto de Seguros Sociales el reconocimiento de la pensi\u00f3n de sobrevivientes. \u00a0<\/p>\n<p>Es decir, dado que el juez de tutela que decidi\u00f3 la primera acci\u00f3n de tutela no tom\u00f3 una decisi\u00f3n sobre la pretensi\u00f3n de reconocimiento de la pensi\u00f3n de sobrevivientes, no existi\u00f3 cosa juzgada en \u00e9ste sentido. As\u00ed, los accionantes quedaron facultados para presentar una nueva acci\u00f3n de tutela con fundamento en la misma pretensi\u00f3n, sin que de ello se pueda concluir que la segunda solicitud de amparo constituye una actuaci\u00f3n temeraria. \u00a0<\/p>\n<p>De acuerdo con lo anterior, en el presente caso no existi\u00f3 una actuaci\u00f3n temeraria por parte de los accionantes, pues como se indic\u00f3, aunque existe identidad de partes y de causa en relaci\u00f3n con una de las pretensiones en las acciones interpuestas, el juez de tutela de la primera de ellas, omiti\u00f3 pronunciarse al respecto en la parte resolutiva de su sentencia.\u00a0 \u00a0<\/p>\n<p>Ahora, quedando desvirtuada la temeridad en la presente acci\u00f3n de tutela, \u00e9sta Sala de Revisi\u00f3n pasar\u00e1 a determinar la procedencia del amparo constitucional invocado por los accionantes.\u00a0 \u00a0<\/p>\n<p>Improcedencia de la presente acci\u00f3n de tutela por incumplimiento del requisito de subsidiariedad.\u00a0 \u00a0<\/p>\n<p>Con base en las consideraciones generales de \u00e9sta Sentencia, la Sala de Revisi\u00f3n determinar\u00e1 si en el presente caso se cumple el requisito de subsidiariedad de la acci\u00f3n de tutela, a fin de establecer la procedencia del amparo constitucional invocado. \u00a0<\/p>\n<p>Para resolver el presente caso, \u00e9sta Sala de Revisi\u00f3n hizo referencia a la regla general seg\u00fan la cual, en desarrollo del principio de subsidiariedad, la acci\u00f3n de tutela es improcedente para ordenar el reconocimiento de un derecho pensional. Al respecto, precis\u00f3 que excepcionalmente, la acci\u00f3n de tutela es procedente como mecanismo transitorio de protecci\u00f3n, \u00a0si de acuerdo con el an\u00e1lisis riguroso de las condiciones particulares del caso concreto y de las pruebas allegadas al proceso, el juez de tutela constata: la inminencia de un perjuicio irremediable a los derechos fundamentales del accionante; \u00a0la afectaci\u00f3n de los derechos fundamentales al m\u00ednimo vital y a la vida digna de \u00e9ste o de su n\u00facleo familiar; la calidad de sujetos de especial protecci\u00f3n constitucional de los beneficiarios del derecho; y, que la decisi\u00f3n de la entidad de negar el reconocimiento del derecho pensional no tiene justificaci\u00f3n legal ni f\u00e1ctica.11 \u00a0<\/p>\n<p>En el presente caso ha quedado demostrado que la interposici\u00f3n de la acci\u00f3n de tutela obedeci\u00f3 a la inconformidad de los accionantes con la decisi\u00f3n del Instituto de Seguros Sociales &#8211; Pensiones seccional Santander de negar el reconocimiento de la pensi\u00f3n de sobrevivientes de su c\u00f3nyuge y madre, la Sra. Ana Consuelo Ayala Vergara.\u00a0 \u00a0<\/p>\n<p>En efecto, mediante las resoluciones No 000967 de 2004 y No 0364 de 2006, el Instituto de Seguros Sociales sostuvo que la Se\u00f1ora Ayala Vergara no cumple los requisitos establecidos en los art\u00edculos 46 de la ley 100 de 1993 y 53 del Decreto 1406 de 1999, para que sus beneficiarios accedan al reconocimiento de la pensi\u00f3n de sobrevivientes. La Entidad explic\u00f3, que al momento de su muerte, la Se\u00f1ora Ayala Vergara \u00a0no se encontraba cotizando al sistema de pensiones, no hab\u00eda realizado aportes durante 26 semanas en el a\u00f1o inmediatamente anterior a la fecha de su deceso y, su empleador hab\u00eda cancelado los aportes atrasados con posterioridad a su fallecimiento, raz\u00f3n por la cual, \u00e9stos no pueden ser tenidos en cuenta para efectos de otorgar el reconocimiento de la pensi\u00f3n a su c\u00f3nyuge e hijas. \u00a0<\/p>\n<p>A diferencia de lo afirmado por la Entidad en las Resoluciones No 000967 de 2004 y No 0364 de 2006, en el escrito de tutela los accionantes sostienen que la Sra. Ayala Vergara al momento de su fallecimiento si cumpl\u00eda con los requisitos exigidos por la ley para acceder al reconocimiento de la pensi\u00f3n de sobrevivientes. Al respecto, aducen que al momento de su muerte, la Sra. Ayala ten\u00eda 939 semanas cotizadas, de las cuales 51 se hab\u00edan efectuado durante el a\u00f1o anterior a su fallecimiento. Agregan que la omisi\u00f3n del Instituto de Seguros Sociales en adelantar las acciones de cobro de los aportes dejados de pagar por parte del empleador, no puede derivar en la negativa del reconocimiento de su derecho pensional.\u00a0 \u00a0<\/p>\n<p>De acuerdo con lo expuesto, y en aplicaci\u00f3n del principio de subsidiariedad de la acci\u00f3n de tutela, la presente solicitud de amparo debe ser negada por improcedente. Ello por cuanto, como se se\u00f1al\u00f3 anteriormente, la acci\u00f3n de tutela es improcedente en los casos en que, como el que se encuentra bajo estudio de \u00e9sta Sala, el accionante tiene a su alcance los recursos o medios ordinarios de defensa judiciales previstos por el legislador para obtener la protecci\u00f3n de sus pretensiones.\u00a0 \u00a0<\/p>\n<p>Si se tiene en cuenta que los accionantes pueden hacer uso de los medios judiciales existentes para cuestionar la decisi\u00f3n del Instituto de Seguros Sociales de denegar de manera definitiva la pensi\u00f3n de sobrevivientes de su c\u00f3nyuge y madre, y obtener de \u00e9sta manera, el amparo de sus pretensiones, la presente acci\u00f3n de tutela debe ser declarada improcedente. Adicionalmente, \u00e9sta Sala debe recordar que el amparo constitucional no es el mecanismo judicial adecuado para tramitar y decidir las controversias o litigios originados en relaci\u00f3n con el reconocimiento de una pensi\u00f3n, pues para ello, el legislador defini\u00f3 los procesos judiciales id\u00f3neos y la jurisdicci\u00f3n encargada de su conocimiento y decisi\u00f3n. \u00a0<\/p>\n<p>Por otro lado, los accionantes no lograron precisar y probar un hecho o circunstancia que permita admitir la procedencia excepcional de la acci\u00f3n de tutela como mecanismo transitorio de protecci\u00f3n. As\u00ed, en el presente caso no existe prueba que permita concluir la ocurrencia de un perjuicio irremediable en el caso en que el juez de instancia denegara la solicitud de tutela. Tampoco existen pruebas que permitan deducir que la decisi\u00f3n desfavorable de la Entidad, haya vulnerado los derechos fundamentales de los accionantes al m\u00ednimo vital o a la vida en condiciones dignas. Es decir, los accionantes no lograron demostrar la necesidad y urgencia de obtener el amparo constitucional, a\u00fan cuando \u00e9ste tuviera un car\u00e1cter transitorio y excepcional. \u00a0<\/p>\n<p>Aunque en el escrito de tutela y en las resoluciones mediante las cuales la entidad accionada neg\u00f3 el derecho pensional, se se\u00f1al\u00f3 que una de las beneficiarias de la pensi\u00f3n de sobrevivientes es una menor de 16 a\u00f1os, los accionantes no demostraron que la negativa del Instituto en el reconocimiento de la pensi\u00f3n de sobrevivientes, haya vulnerado o amenazado sus derechos fundamentales o haya afectado su calidad de vida. Si bien se trata de un sujeto de especial protecci\u00f3n constitucional, su representante no aport\u00f3 pruebas acerca de sus \u201ccondiciones sicol\u00f3gicas (sic) dif\u00edciles\u201d, y del nexo de causalidad entre la decisi\u00f3n del Instituto de Seguros Sociales y dichas condiciones. \u00a0<\/p>\n<p>Por \u00faltimo, esta Sala considera necesario resaltar que, conforme a los hechos indicados por los accionantes en el escrito de tutela, la Sra. Ayala Vergara ocupaba el cargo de Directora Administrativa en la Sociedad Ayala Vergara Ltda. y que en tal condici\u00f3n, estuvo afiliada al Instituto de Seguros Sociales \u2013 Pensiones.\u00a0 \u00a0<\/p>\n<p>Al respecto, cabe se\u00f1alar que de acuerdo a las normas que regulan la materia12, en las compa\u00f1\u00edas de responsabilidad limitada -como es el caso de la Sociedad Ayala Vergara Ltda.-, los aportes, as\u00ed como la responsabilidad de los socios implican una relaci\u00f3n de participaci\u00f3n en la sociedad que no puede ser separada de la persona del socio. En este sentido, dado que la Sra. Ayala Vergara ejerc\u00eda el cargo de direcci\u00f3n administrativa en la Sociedad en comento, se puede afirmar que aquella deb\u00eda estar al tanto de los pagos y cotizaciones de los trabajadores de la compa\u00f1\u00eda al sistema de seguridad social en salud y pensiones. Es decir, se puede estimar que era de su conocimiento la mora de la Sociedad Ayala Vergara Ltda. en el pago de los aportes al Instituto de Seguros Sociales \u2013 Pensiones en calidad de empleador. Mora que seg\u00fan las resoluciones No 000967 de 2004 y No 0364 de 2006 expedidas por el Instituto de Seguros Sociales, constituy\u00f3 parte de los argumentos expuestos por la Entidad para negar la pensi\u00f3n de sobrevivientes reclamada por los accionantes. \u00a0 \u00a0<\/p>\n<p>Ahora -adem\u00e1s de las razones expuestas en las consideraciones de esta Providencia-, no es admisible que los causahabientes de la Sra. Ayala Vergara pretendan a trav\u00e9s de la acci\u00f3n de tutela obtener el reconocimiento de la pensi\u00f3n de sobrevivientes, si se considera que dicha Se\u00f1ora, conforme al cargo que ocupaba en la Sociedad Ayala Vergara Ltda., deb\u00eda tener conocimiento de la mora en que incurri\u00f3 su empleador en el pago de los aportes al Instituto de Seguros Sociales y pod\u00eda adelantar las gestiones necesarias para evitarla o solucionarla mediante los pagos correspondientes. \u00a0<\/p>\n<p>En s\u00edntesis, ya que los accionantes pueden hacer uso de los mecanismos ordinarios de defensa judicial previstos por el legislador para obtener la protecci\u00f3n de sus derechos y no existen pruebas para conceder la tutela como mecanismo transitorio, por incumplimiento del requisito de subsidiariedad, la acci\u00f3n de tutela bajo estudio de \u00e9sta Sala deber\u00e1 ser declarada improcedente.\u00a0 \u00a0<\/p>\n<p>En virtud de lo expresado anteriormente, \u00e9sta Sala de Revisi\u00f3n confirmar\u00e1 la decisi\u00f3n del Juzgado Segundo de Familia de Bucaramanga que mediante sentencia del d\u00eda 6 de septiembre de 2006, declar\u00f3 improcedente la presente acci\u00f3n de tutela.\u00a0 \u00a0<\/p>\n<p>IV. DECISI\u00d3N\u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Primera de Revisi\u00f3n de la Corte Constitucional, administrando justicia en nombre del pueblo, y por mandato de la Constituci\u00f3n Pol\u00edtica, \u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>Primero. CONFIRMAR la decisi\u00f3n adoptada el seis (6) de septiembre de 2006 por el Juzgado Segundo de Familia de Bucaramanga mediante la cual declar\u00f3 improcedente la acci\u00f3n de tutela interpuesta por Andrea Paola Monta\u00f1ez Ayala y Aureliano Monta\u00f1ez Pinz\u00f3n quien act\u00faa en nombre propio y en representaci\u00f3n de la menor \u00c1ngela Mar\u00eda Monta\u00f1ez Ayala, dentro del tr\u00e1mite de la acci\u00f3n instaurada contra el Instituto de Seguros Sociales \u2013 Pensiones Seccional Santander.\u00a0 \u00a0<\/p>\n<p>Segundo. D\u00c9SE cumplimiento a lo dispuesto en el art\u00edculo 36 del Decreto 2591 de 1991. \u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese, publ\u00edquese en la gaceta de la Corte Constitucional y c\u00famplase. \u00a0<\/p>\n<p>JAIME ARA\u00daJO RENTER\u00cdA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>MANUE JOS\u00c9 CEPEDA ESPINOSA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>JAIME C\u00d3RDOBA TRIVI\u00d1O \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA DE MONCALEANO \u00a0<\/p>\n<p>Secretaria General \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 Ver entre muchas otras, las sentencias: T-885 de 2006, T-407 de 2005, T-986 de 2004, \u00a0T-336 de 2004 y T-553 de 1999. \u00a0<\/p>\n<p>2 En la sentencia T-707 de 2003, la Corte tutel\u00f3 los derechos fundamentales a la vida y al m\u00ednimo vital de un ex &#8211; alcalde que solicitaba el pago de los salarios del per\u00edodo de 1996 a 1999. El actor hab\u00eda interpuesto una primera acci\u00f3n de tutela por afectaci\u00f3n de su derecho fundamental al m\u00ednimo vital la cual fue denegada. Aunque la motivaci\u00f3n de la segunda acci\u00f3n de tutela se deriv\u00f3 de los mismos hechos de la primera, durante el tr\u00e1mite de aquella el accionante prob\u00f3 el padecimiento de una grave enfermedad. As\u00ed, la Corte rechaz\u00f3 la existencia de temeridad y tutel\u00f3 los derechos fundamentales del actor en virtud de los nuevos hechos demostrados. \u00a0<\/p>\n<p>En la sentencia T- 812 de 2005 la Corte declar\u00f3 la improcedencia parcial de la acci\u00f3n de tutela con relaci\u00f3n a una de las pretensiones de la accionante por la vulneraci\u00f3n de su derecho fundamental al debido proceso dentro del tr\u00e1mite de un proceso ejecutivo hipotecario. En \u00e9sta oportunidad, la Corte concluy\u00f3 que si bien la accionante hab\u00eda interpuesto tres acciones de tutela con fundamento en una misma pretensi\u00f3n, frente a la acci\u00f3n de tutela objeto de revisi\u00f3n exist\u00edan nuevas pretensiones que deb\u00edan ser analizadas por la Corte. Adicionalmente, en virtud de la presunci\u00f3n de buena fe, desestim\u00f3 una actuaci\u00f3n temeraria por parte de la actora.\u00a0 \u00a0<\/p>\n<p>En la sentencia T-433 de 2006 la Corte confirm\u00f3 el fallo de tutela que declar\u00f3 la existencia de una actuaci\u00f3n temeraria e impuso al accionante el pago de las costas del proceso por la presentaci\u00f3n de tres acciones de tutela con base en los mismos hechos y pretensiones. En \u00e9sta oportunidad, la Corte analiz\u00f3 la presunta vulneraci\u00f3n del derecho fundamental al debido proceso de una persona condenada a pena privativa de la libertad por el delito de estafa. Al respecto, la Corte determin\u00f3 que de manera dolosa el actor emple\u00f3 la estrategia de incluir \u00a0nuevas pretensiones y nuevos accionados a fin de evitar la configuraci\u00f3n de una actuaci\u00f3n temeraria. \u00a0<\/p>\n<p>3 En \u00e9ste sentido, en la sentencia T-1134 de 2005, la Corte se\u00f1al\u00f3 que los elementos de la actuaci\u00f3n temeraria, as\u00ed como la sanci\u00f3n prevista para ello en el art\u00edculo 38 del Decreto 2591 de 1991, deben ser ampliadas con los art\u00edculos 72 a 74 del C\u00f3digo de Procedimiento Civil. Ver entre otras, las sentencias: T-502 de 2003 y T-080 de 1998. \u00a0<\/p>\n<p>4 Ver entre otras, la sentencia T-159 de 2006, T-410 de 2005 y T-082 de 2004. \u00a0<\/p>\n<p>5 En la sentencia T-939 de 2006, la Corte precis\u00f3: \u201cComo antes se expuso, la acci\u00f3n de tutela de la referencia tiene los mismos fundamentos que la primera. Otra cosa diferente es que en la medida en que no se demostr\u00f3 la actuaci\u00f3n de mala fe por parte del apoderado del accionante no se re\u00fanan los requisitos se\u00f1alados por la jurisprudencia para considerar que la segunda de la acciones es temeraria. En este orden de ideas, no hay lugar a la imposici\u00f3n de las sanciones previstas en el Decreto 2591 de 1991 por conducta temeraria.\u201d\u00a0 \u00a0<\/p>\n<p>En aplicaci\u00f3n de \u00e9sta regla, en la sentencia T-919 de 2003 la Corte declar\u00f3 la improcedencia de la acci\u00f3n de tutela interpuesta por un paciente de VIH por la vulneraci\u00f3n de su derecho fundamental a la vida. A pesar de tener un fallo de tutela favorable para la entrega de algunos medicamentos, el accionante interpuso una nueva acci\u00f3n de tutela con base en los mismos hechos, contra el mismo accionado y con las mismas pretensiones, pues la EPS no cumpli\u00f3 las \u00f3rdenes del primer fallo de tutela. En \u00e9ste caso, la Corte estim\u00f3 que el accionante no act\u00fao de manera contraria al principio de la buena fe, ya que la segunda acci\u00f3n de tutela se fund\u00f3 en la necesidad extrema de defender sus derechos fundamentales; raz\u00f3n por la cual no era procedente la imposici\u00f3n de una sanci\u00f3n por temeridad. \u00a0<\/p>\n<p>6 Ver, entre muchas otras, las sentencias: T-1140 de 2004, T-1093 de 2004, T-514 de 2003 y T-1121 de 2003. \u00a0<\/p>\n<p>7 Ver ente otras, las sentencias: T-656 de 2006, T-435 de 2006, T-768 de 2005, T-651 de 2004, y T-1012 de 2003. \u00a0<\/p>\n<p>8 Ver entre otras, las sentencias:T-685 de 2006, T-203 de 2006, T-973 de 2005, T-691 de 2005, T-443 de 2005 y T-425 de 2004. \u00a0<\/p>\n<p>9 Ver entre muchas otras, las sentencias: T-848 de 2006, T-990 de 2005, T-996 de 2005, T-917 de 2005 y T-627 de 2005. \u00a0<\/p>\n<p>10 Ver entre otras, las sentencias: T-816 de 2006, T-1309 de 2005, T-691 de 2005, T-580 de 2005 y T-425 de 2004.\u00a0 \u00a0<\/p>\n<p>En la sentencia T-605 de 2005 la Corte tutel\u00f3 los derechos fundamentales a la vida y al m\u00ednimo vital de un funcionario diplom\u00e1tico cuya pensi\u00f3n no fue liquidada por CAJANAL conforme al salario devengado por el accionante. En \u00e9sta caso, la Corte consider\u00f3 que, dado que el accionante era una persona de la tercera edad, y que por lo tanto, la carga de adelantar una acci\u00f3n ordinaria para obtener la reliquidaci\u00f3n de su pensi\u00f3n resultaba desproporcionada, la acci\u00f3n de tutela era procedente como mecanismo transitorio a fin de evitar un perjuicio irremediable.\u00a0 \u00a0<\/p>\n<p>En la sentencia T-971 de 2005, la Corte tutel\u00f3 los derechos fundamentales al m\u00ednimo vital de una familia desplazada cuya solicitud de reconocimiento de una pensi\u00f3n de sobrevivientes fue negada por Colfondos S.A. En \u00e9ste caso, la Corte estim\u00f3 que la negativa de la Entidad no se fundamentaba el incumplimiento de los requisitos para ejercicio del derecho a la pensi\u00f3n de sobrevivientes, pues de acuerdo con las pruebas allegadas al proceso, la aseguradora Colpatria, con quien Colfondos S.A. suscribi\u00f3 el contrato de seguro para el cubrimiento de las sumas adicionales previstas en el art\u00edculo 70 de la Ley 100 de 1993, se negaba a transferir el valor de dichas sumas. Adicionalmente, la Corte se\u00f1al\u00f3 que como consecuencia de su situaci\u00f3n de desplazamiento, los accionantes se encontraban sujetos a condiciones de extrema vulnerabilidad. En consecuencia la Corte orden\u00f3 el reconocimiento y pago de la pensi\u00f3n de sobrevivientes. \u00a0<\/p>\n<p>En la sentencia T-859 de 2004, la Corte tutel\u00f3 los derechos fundamentales al m\u00ednimo vital de una mujer discapacitada cuya solicitud de reconocimiento de la pensi\u00f3n de la pensi\u00f3n de sobrevivientes de su madre le fue negada. En el presente caso, la Corte determin\u00f3 que de acuerdo con el acervo probatorio de la acci\u00f3n de tutela, la accionante cumpl\u00eda con los requisitos exigidos por la ley para el reconocimiento del derecho pensional, y se encontraba en un estado de invalidez mental que le imped\u00eda llevar a cabo una actividad laboral para garantizar su sustento. En consecuencia, la Corte orden\u00f3 que la entidad responsable hiciera efectivo el reconocimiento y pago de la pensi\u00f3n de sobrevivientes, hasta tanto la jurisdicci\u00f3n ordinaria, dirimiera las controversias existentes entre \u00e9sta y la accionante sobre el derecho pensional. \u00a0<\/p>\n<p>11 Acerca de la procedencia de la acci\u00f3n de tutela en los casos en que la entidad responsable neg\u00f3 el reconocimiento de derecho pensional en virtud de la configuraci\u00f3n de una v\u00eda de hecho, se pueden consultar las sentencias: T-1309 de 2005, \u00a0T-996 de 2005, y T-235 de 2002. \u00a0<\/p>\n<p>12 T\u00edtulo V, Libro Primero, C\u00f3digo de Comercio. \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia T-184\/07 \u00a0 ACCION DE TUTELA TEMERARIA-Elementos para su configuraci\u00f3n \u00a0 ACCION DE TUTELA-Subsidiariedad\/ACCION DE TUTELA-Improcedencia para ordenar reconocimiento de pensiones \u00a0 ACCION DE TUTELA-Procedencia excepcional para ordenar reconocimiento de pensiones\u00a0 \u00a0 ACCION DE TUTELA-Inexistencia de temeridad para el caso \u00a0 ACCION DE TUTELA-Improcedencia por no demostraci\u00f3n de perjuicio irremediable ni vulneraci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-14373","post","type-post","status-publish","format-standard","hentry","category-tutelas-2007"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/14373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=14373"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/14373\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=14373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=14373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=14373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}