{"id":16617,"date":"2024-06-07T20:45:52","date_gmt":"2024-06-07T20:45:52","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/06\/07\/t-163-09\/"},"modified":"2024-06-07T20:45:52","modified_gmt":"2024-06-07T20:45:52","slug":"t-163-09","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-163-09\/","title":{"rendered":"T-163-09"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia T-163-09 \u00a0<\/p>\n<p>(Marzo 16, Bogot\u00e1 DC.) \u00a0<\/p>\n<p>Referencia: \u00a0Expediente T-2.074.102. \u00a0\u00a0<\/p>\n<p>Accionante: \u00a0Roger \u00a0Rafael Rambao Guti\u00e9rrez. \u00a0\u00a0<\/p>\n<p>Accionado: \u00a0Seguro \u00a0Social EPS y Nueva EPS \u00a0\u00a0<\/p>\n<p>Fallo \u00a0 objeto \u00a0de \u00a0revisi\u00f3n: \u00a0sentencia \u00a0del \u00a0Juzgado Penal del Circuito de Soledad -Atl\u00e1ntico, \u00a0del \u00a0 \u00a0 \u00a0 7 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0mayo \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a020081 (no impugnada). \u00a0\u00a0<\/p>\n<p>Magistrados \u00a0 de \u00a0 la \u00a0 Sala \u00a0 Quinta \u00a0 de \u00a0Revisi\u00f3n: \u00a0Mauricio \u00a0Gonz\u00e1lez \u00a0Cuervo, \u00a0Cristina \u00a0Pardo \u00a0Schlesinger y Nilson Pinilla Pinilla.\u00a0 \u00a0\u00a0<\/p>\n<p>Magistrado Ponente: \u00a0Mauricio Gonz\u00e1lez Cuervo. \u00a0\u00a0<\/p>\n<p>I. ANTECEDENTES. \u00a0<\/p>\n<p>1. Demanda y pretensi\u00f3n. \u00a0<\/p>\n<p>El \u00a0 \u00a0se\u00f1or \u00a0 \u00a0Roger \u00a0 \u00a0Rafael \u00a0 Rambao \u00a0Guti\u00e9rrez \u00a0 \u00a0 \u00a02 present\u00f3 acci\u00f3n de tutela en \u00a0contra del Seguro Social EPS, as\u00ed: \u00a0\u00a0<\/p>\n<p>1.1. \u00a0 \u00a0 \u00a0Derechos \u00a0 \u00a0 fundamentales \u00a0vulnerados: \u00a0derecho \u00a0a \u00a0la \u00a0vida, \u00a0a \u00a0la \u00a0salud, a la \u00a0seguridad \u00a0social, \u00a0al \u00a0trabajo, \u00a0al \u00a0libre \u00a0desarrollo de la personalidad, a la \u00a0igualdad y a la libertad de autodeterminaci\u00f3n. \u00a0\u00a0<\/p>\n<p>1.2. \u00a0 \u00a0 Vulneraci\u00f3n: \u00a0 \u00a0la \u00a0negativa \u00a0de \u00a0la \u00a0accionada \u00a0de \u00a0autorizar \u00a0la \u00a0cirug\u00eda BY PASS \u00a0G\u00c1STRICO, \u00a0que \u00a0considera \u00a0requiere para mejorar su estado por padecer obesidad \u00a0m\u00f3rbida. \u00a0\u00a0<\/p>\n<p>1.3. Pretensi\u00f3n: se \u00a0ordene \u00a0a la accionada expedir las \u00f3rdenes pertinentes para que se le practique \u00a0la \u00a0Cirug\u00eda \u00a0By \u00a0Pass G\u00e1strico por Laparoscopia y se suministre el tratamiento \u00a0integral \u00a0para \u00a0el \u00a0manejo \u00a0de \u00a0la \u00a0obesidad \u00a0m\u00f3rbida \u00a0que \u00a0padece. \u00a0\u00a0<\/p>\n<p>1.4. \u00a0 \u00a0 \u00a0Fundamento \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0la \u00a0pretensi\u00f3n: \u00a0 (i) \u00a0 la \u00a0 cirug\u00eda \u00a0solicitada \u00a0busca \u00a0\u201caliviar \u00a0el \u00a0intenso dolor que presenta desde hace \u00a0mucho \u00a0 tiempo \u00a0 a \u00a0 consecuencia \u00a0de \u00a0todas \u00a0las \u00a0enfermedades \u00a0que \u00a0padece\u201d, \u00a0y \u00a0encontrar \u00a0una \u00a0soluci\u00f3n \u00a0definitiva a la obesidad \u00a0m\u00f3rbida \u00a0que \u00a0le \u00a0fue \u00a0diagnosticada; \u00a0(ii) no ha podido solucionar su problema \u00a0pese \u00a0al agotamiento de diferentes tratamientos que resultaron infructuosos para \u00a0bajar \u00a0de \u00a0peso; \u00a0(iii) \u00a0el requerido tiene un costo que supera los $18.000.000, \u00a0suma \u00a0que no est\u00e1 en capacidad de asumir, toda vez que no cuenta con los medios \u00a0econ\u00f3micos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0suficientes3. \u00a0\u00a0<\/p>\n<p>2. \u00a0 \u00a0Respuesta \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0entidad \u00a0demandada. \u00a0\u00a0<\/p>\n<p>Mediante \u00a0Oficio No. 940-08, del 22 de abril \u00a0del \u00a0 \u00a020084, \u00a0el \u00a0Juzgado Penal del Circuito de Soledad Atl\u00e1ntico comunic\u00f3 al \u00a0Seguro \u00a0Social EPS la admisi\u00f3n de la tutela y concedi\u00f3 el t\u00e9rmino de ley para \u00a0que \u00a0la \u00a0entidad \u00a0accionada \u00a0emitiera \u00a0un pronunciamiento respecto de los hechos \u00a0demandados \u00a0y \u00a0solicitara \u00a0pruebas en su favor, de estimarlo pertinente, sin que \u00a0diera \u00a0respuesta \u00a0alguna \u00a0en \u00a0el \u00a0tr\u00e1mite \u00a0propio \u00a0de \u00a0la \u00a0acci\u00f3n \u00a0de \u00a0tutela. \u00a0\u00a0<\/p>\n<p>3. Hechos y medios de prueba. \u00a0<\/p>\n<p>&#8211; \u00a0El se\u00f1or Roger Rafael Rambao es afiliado \u00a0del \u00a0r\u00e9gimen \u00a0contributivo \u00a0del \u00a0Sistema \u00a0General de Seguridad Social en Salud, \u00a0como cotizante. \u00a0\u00a0<\/p>\n<p>&#8211; \u00a0El \u00a0actor \u00a0ha \u00a0sido \u00a0valorado \u00a0por varios \u00a0especialistas \u00a0y \u00a0un \u00a0equipo m\u00e9dico multidisciplinario adscrito al ISS, quienes \u00a0concluyeron \u00a0que \u00a0necesita \u00a0la Cirug\u00eda By Pass G\u00e1strico para mejorar su estado \u00a0de \u00a0salud, \u00a0el \u00a0cual \u00a0se \u00a0ha venido deteriorando toda vez que padece de obesidad \u00a0m\u00f3rbida5: \u00a0 \u00a0 (i) \u00a0 \u00a0el \u00a0 \u00a0especialista \u00a0 \u00a0m\u00e9dico \u00a0 \u00a0internista6, doctor Pedro \u00a0Trillos \u00a0Franco \u00a0adscrito \u00a0al \u00a0ISS, \u00a0a trav\u00e9s de la IPS centro de diagnostico y \u00a0rehabilitaci\u00f3n, \u00a0dictamin\u00f3: \u00a0\u201cpaciente \u00a0quien \u00a0se \u00a0encuentra \u00a0 \u00a0en \u00a0 \u00a0programaci\u00f3n \u00a0 \u00a0de \u00a0 \u00a0cirug\u00eda \u00a0 \u00a0bari\u00e1trica\u201d7; \u00a0 (ii) \u00a0la \u00a0doctora \u00a0Mahra \u00a0Machac\u00f3n, \u00a0psic\u00f3loga \u00a0de la misma IPS manifest\u00f3: \u201cpaciente \u00a0 de \u00a0 53 \u00a0a\u00f1os \u00a0de \u00a0edad \u00a0que \u00a0asiste \u00a0a \u00a0psicolog\u00eda \u00a0presentando \u00a0un \u00a0sobrepeso \u00a0el \u00a0cual \u00a0est\u00e1 \u00a0apto \u00a0para el inicio del proceso de \u00a0operaci\u00f3n \u00a0 en \u00a0 lo \u00a0 concerniente \u00a0 de \u00a0 su \u00a0 estado \u00a0emocional\u201d8; \u00a0(iii) \u00a0el \u00a0doctor \u00a0Jaime \u00a0Vel\u00e1zquez \u00a0Berm\u00fadez \u00a0adscrito al ISS, a trav\u00e9s de la IPS CECAM \u00a0NORTE \u00a0conceptu\u00f3: \u00a0\u201cpaciente \u00a0que \u00a0se \u00a0someter\u00e1 a \u00a0CIRUG\u00cdA \u00a0DE \u00a0OBESIDAD \u00a0BARI\u00c1TRICA, se solicita valoraci\u00f3n\u00a0 cirug\u00eda para \u00a0la \u00a0 \u00a0 Cl\u00ednica \u00a0 \u00a0 Reina \u00a0 \u00a0Catalina\u201d9; \u00a0y \u00a0(iv) \u00a0su \u00a0m\u00e9dico \u00a0tratante \u00a0doctor Jes\u00fas Habid Cure Michailith, especialista en Cirug\u00eda \u00a0en \u00a0General \u00a0&#8211; \u00a0Laparoscop\u00eda \u00a0Avanzada-, \u00a0Endoscopia \u00a0V\u00edas \u00a0Digestivas, \u00a0quien \u00a0reafirma \u00a0el \u00a0concepto \u00a0dado por los especialistas adscritos al ISS, se\u00f1alando: \u00a0\u201cPaciente \u00a0con \u00a0diagnostico \u00a0de \u00a0OBESIDAD \u00a0M\u00d3RBIDA \u00a0SEVERA\u2026se \u00a0indica \u00a0manejo \u00a0quir\u00fargico CIRUG\u00cdA BARI\u00c1TRICA (sleeve g\u00e1strico) \u00a0por \u00a0 \u00a0 \u00a0 \u00a0 \u00a0video \u00a0 \u00a0 \u00a0 \u00a0 \u00a0laparoscopia\u201d10. \u00a0\u00a0<\/p>\n<p>&#8211; \u00a0El se\u00f1or Roger Rafael Rambao Guti\u00e9rrez, \u00a0con \u00a0fundamento \u00a0en \u00a0su situaci\u00f3n patol\u00f3gica dictaminada por los especialistas \u00a0de \u00a0la \u00a0respectiva EPS, radic\u00f3 un derecho de petici\u00f3n ante el ISS, solicitando \u00a0se \u00a0le \u00a0autorizara \u00a0con urgencia la CIRUG\u00cdA BARI\u00c1TRICA POR VIDEO LAPAROSCOPIA, \u00a0recomendada \u00a0 por \u00a0 su \u00a0m\u00e9dico \u00a0tratante, \u00a0adscrito \u00a0y \u00a0activo \u00a0en \u00a0la \u00a0red \u00a0de \u00a0especialistas \u00a0de \u00a0CECAMP. \u00a0Sin \u00a0embargo \u00a0la \u00a0EPS-ISS, \u00a0luego \u00a0de \u00a0programar \u00a0la \u00a0cirug\u00eda11, \u00a0y \u00a0previo \u00a0a \u00a0los \u00a0ex\u00e1menes de rigor12, \u00a0 decide \u00a0 no \u00a0expedir \u00a0la \u00a0autorizaci\u00f3n correspondiente. \u00a0\u00a0<\/p>\n<p>&#8211; Mediante oficio GSA-DMC. No. 1358 del 19 de \u00a0noviembre \u00a0 de \u00a0 2007, \u00a0 el \u00a0 Seguro \u00a0 Social \u00a0 dio \u00a0 respuesta \u00a0al \u00a0derecho \u00a0de \u00a0petici\u00f3n13 \u00a0 presentado \u00a0 por \u00a0 el \u00a0se\u00f1or \u00a0Roger \u00a0Rafael \u00a0Rambao \u00a0Guti\u00e9rrez, \u00a0manifest\u00e1ndole \u00a0que: \u201c(\u2026) Por estar asignado a la \u00a0unidad \u00a0Cecam \u00a0Norte, \u00a0en \u00a0su \u00a0proceso \u00a0de atenci\u00f3n, se ha solicitado a ella la \u00a0convocatoria \u00a0de \u00a0la \u00a0junta; \u00a0cuando \u00a0se tenga la fecha de la realizaci\u00f3n se le \u00a0estar\u00e1 avisando oportunamente\u201d.\u00a0 \u00a0\u00a0<\/p>\n<p>&#8211; \u00a0 El \u00a0 accionante \u00a0 busca \u00a0 \u201caliviar \u00a0el intenso dolor que presenta desde hace mucho tiempo a \u00a0consecuencia \u00a0de \u00a0todas las enfermedades que padece\u201d, \u00a0resaltando \u00a0que \u00a0no cuenta con los medios econ\u00f3micos suficientes para asumir el \u00a0costo \u00a0 de \u00a0 esta \u00a0 cirug\u00eda \u00a0cuyo \u00a0valor \u00a0supera \u00a0los \u00a0$18.000.000.14 \u00a0\u00a0<\/p>\n<p>4. Fallo objeto de revisi\u00f3n. Sentencia del 8 \u00a0de \u00a0 mayo \u00a0de \u00a02008 \u00a0del \u00a0Juzgado \u00a0Penal \u00a0del \u00a0Circuito \u00a0de \u00a0Soledad\u2013Atl\u00e1ntico \u00a0 (sentencia \u00a0 \u00fanica \u00a0 de \u00a0instancia). \u00a0\u00a0<\/p>\n<p>4.1. \u00a0El \u00a0juez \u00a0de \u00a0instancia no tutel\u00f3 los \u00a0derechos \u00a0del \u00a0accionante. \u00a0Consider\u00f3 \u00a0que \u00a0no \u00a0existe \u00a0concordancia \u00a0entre \u00a0lo \u00a0manifestado \u00a0por \u00a0el \u00a0se\u00f1or \u00a0Roger \u00a0Rafael \u00a0Rambao \u00a0Guti\u00e9rrez \u00a0y \u00a0las \u00a0pruebas \u00a0aportadas \u00a0en \u00a0el \u00a0expediente, \u00a0resaltando \u00a0que \u00a0\u201clo \u00a0solicitado \u00a0por \u00a0el actor no fue la realizaci\u00f3n de la cirug\u00eda bari\u00e1trica sino \u00a0una \u00a0 \u00a0 Junta \u00a0 \u00a0 M\u00e9dica \u00a0 \u00a0de \u00a0 \u00a0Valoraci\u00f3n\u201d15. \u00a0\u00a0<\/p>\n<p>4.2. \u00a0Fundamentos de la decisi\u00f3n: (i) no se \u00a0encontr\u00f3 \u00a0el \u00a0estudio \u00a0del \u00a0Comit\u00e9 \u00a0T\u00e9cnico \u00a0Cient\u00edfico \u00a0o Junta M\u00e9dica del \u00a0Seguro \u00a0Social \u00a0-EPS-, \u00a0o en su defecto, de la entidad CECAMP, sobre si la orden \u00a0presentada \u00a0por \u00a0el \u00a0doctor \u00a0Jes\u00fas \u00a0Habit \u00a0Cure Michailith, m\u00e9dico tratante de \u00a0Roger \u00a0 \u00a0Rafael \u00a0 \u00a0Rambao, \u00a0 \u00a0deb\u00eda \u00a0 \u00a0o \u00a0 \u00a0no \u00a0 \u00a0ser \u00a0 \u00a0autorizada \u00a0 (cirug\u00eda \u00a0bari\u00e1tica)16; \u00a0(ii) resalt\u00f3 que no puede existir dicha valoraci\u00f3n pues como se \u00a0se\u00f1al\u00f3 \u00a0la \u00a0EPS \u00a0Instituto \u00a0de \u00a0Seguro \u00a0Social, \u00a0a \u00a0trav\u00e9s \u00a0del \u00a0oficio antes \u00a0se\u00f1alado \u00a0expres\u00f3 \u00a0que \u00a0una vez se tuviera la fecha para valoraci\u00f3n por junta \u00a0m\u00e9dica \u00a0le \u00a0estar\u00eda \u00a0notificando \u00a0al \u00a0actor; \u00a0(iv) \u00a0en \u00a0el \u00a0expediente no obra \u00a0notificaci\u00f3n \u00a0alguna \u00a0y \u00a0mucho menos conformaci\u00f3n de comit\u00e9 para evaluaci\u00f3n, \u00a0\u201csolo \u00a0 existe \u00a0 como \u00a0 prueba \u00a0 una \u00a0 especie \u00a0de \u00a0certificaci\u00f3n \u00a0expedida \u00a0por la Psic\u00f3loga Mahra Machac\u00f3n, en la que se indica \u00a0que \u00a0asiste \u00a0a consulta sin que se especifique desde cuando y que esta apto para \u00a0inicio \u00a0de \u00a0proceso \u00a0de \u00a0operaci\u00f3n: \u00a0una \u00a0hoja de historia cl\u00ednica en donde se \u00a0indica \u00a0en \u00a0la \u00a0parte \u00a0de motivo &#8220;PCT QUE CONSULTA POR \u00a0QUE \u00a0SE \u00a0QUIERE \u00a0OPERAR \u00a0CIRUG\u00cdA \u00a0BARI\u00c1TRICA&#8221; \u00a0y un \u00a0control \u00a0 por \u00a0 nutricionista \u00a0 doctora \u00a0 Evina \u00a0 Llerena, \u00a0sin \u00a0que \u00a0 especifique \u00a0 desde \u00a0 cuando \u00a0esta \u00a0en \u00a0control\u201d. \u00a0Con \u00a0base en lo anterior, se consider\u00f3 \u00a0que \u00a0no \u00a0ha \u00a0existido vulneraci\u00f3n alguna a los derechos del accionante toda vez \u00a0que \u00a0no \u00a0existe \u00a0prueba de que la accionada haya negado la mencionada cirug\u00eda y \u00a0por \u00a0el contrario, resalta la ausencia de la valoraci\u00f3n m\u00e9dico cient\u00edfica por \u00a0parte del comit\u00e9 m\u00e9dico. \u00a0\u00a0<\/p>\n<p>4.3. \u00a0Sin \u00a0embargo, \u00a0el \u00a0fallador \u00a0decidi\u00f3 \u00a0exhortar \u00a0a \u00a0la \u00a0EPS \u00a0Instituto Seguro Social, \u201cpara \u00a0que \u00a0proceda \u00a0a se\u00f1alar fecha para la evaluaci\u00f3n por parte del Comit\u00e9 M\u00e9dico \u00a0Cient\u00edfico, \u00a0a \u00a0fin de que este valore las condiciones de salud del actor ROGER \u00a0RAFAEL \u00a0RAMBAO \u00a0GUTI\u00c9RREZ, \u00a0y \u00a0de \u00a0requerir \u00a0la \u00a0cirug\u00eda Bari\u00e1tica proceda la \u00a0accionada \u00a0a \u00a0la \u00a0pr\u00e1ctica de todos los ex\u00e1menes y procedimientos que requiera \u00a0como \u00a0preparaci\u00f3n \u00a0para \u00a0la \u00a0cirug\u00eda, as\u00ed como la realizaci\u00f3n de la cirug\u00eda \u00a0misma \u00a0de acuerdo con la prescripci\u00f3n que efectu\u00f3 su m\u00e9dico tratante, siempre \u00a0que \u00a0el \u00a0paciente \u00a0consienta en ello y que de los ex\u00e1menes que se practiquen no \u00a0se \u00a0concluya \u00a0que el estado de salud del se\u00f1or ROGER RAMBAO impide la pr\u00e1ctica \u00a0de la referida cirug\u00eda\u201d. \u00a0\u00a0<\/p>\n<p>5. Tr\u00e1mite en sede de revisi\u00f3n \u00a0<\/p>\n<p>El \u00a0Magistrado \u00a0Ponente, \u00a0en \u00a0virtud \u00a0de \u00a0la \u00a0liquidaci\u00f3n \u00a0de \u00a0la \u00a0EPS \u00a0del \u00a0Seguro \u00a0Social y la entrada en operaciones de la \u00a0Nueva \u00a0 EPS18, \u00a0profiri\u00f3 \u00a0el \u00a011 \u00a0de diciembre de 2008 auto con el prop\u00f3sito de \u00a0integrar \u00a0a \u00a0esta \u00a0\u00faltima \u00a0entidad \u00a0al proceso de la referencia, ya que para la \u00a0fecha \u00a0en \u00a0que \u00a0se \u00a0interpuso la acci\u00f3n a\u00fan no se encontraba en operaci\u00f3n. En \u00a0este \u00a0auto \u00a0se\u00a0 \u00a0concedi\u00f3 el t\u00e9rmino de dos d\u00edas\u00a0 para que la Nueva \u00a0EPS \u00a0se \u00a0manifestara sobre la acci\u00f3n de tutela en curso y solicitara pruebas en \u00a0su \u00a0favor \u00a0si \u00a0as\u00ed \u00a0lo \u00a0estimaba \u00a0pertinente; \u00a0sin embargo, la Nueva EPS no dio \u00a0respuesta \u00a0 \u00a0alguna \u00a0 \u00a0durante \u00a0 el \u00a0 tr\u00e1mite \u00a0 dado \u00a0 en \u00a0 la \u00a0 instancia \u00a0 de \u00a0revisi\u00f3n19. \u00a0\u00a0<\/p>\n<p>En \u00a0 comunicaci\u00f3n \u00a0 establecida \u00a0 con \u00a0el \u00a0accionante, \u00a0Roger \u00a0Rafael Rambao Guti\u00e9rrez, el 3 de febrero del a\u00f1o en curso, \u00a0\u00e9ste \u00a0manifest\u00f3 \u00a0que \u00a0la \u00a0cirug\u00eda ya le hab\u00eda sido practicada por su m\u00e9dico \u00a0tratante. \u00a0Por \u00a0lo \u00a0anterior, \u00a0este \u00a0despacho \u00a0solicit\u00f3 al doctor Jos\u00e9 H. Cure \u00a0Michailith, \u00a0m\u00e9dico \u00a0tratante del accionante que informara cu\u00e1ndo se le hab\u00eda \u00a0practicado \u00a0la \u00a0cirug\u00eda \u00a0al \u00a0se\u00f1or \u00a0Rambao. Es as\u00ed que\u00a0 mediante informe \u00a0secretarial \u00a0del \u00a025 \u00a0de \u00a0febrero, se alleg\u00f3 a este despacho certificaci\u00f3n del \u00a0doctor \u00a0Cure \u00a0en \u00a0la \u00a0que hace constar que \u201cel 29 de \u00a0enero \u00a0de \u00a02009, \u00a0se \u00a0le \u00a0practic\u00f3 \u00a0el \u00a0procedimiento \u00a0quir\u00fargico \u00a0de cirug\u00eda \u00a0bari\u00e1trica \u00a0al \u00a0paciente \u00a0Roger \u00a0Rambao, \u00a0el \u00a0cual \u00a0fue autorizado por la Nueva \u00a0EPS\u201d. \u00a0\u00a0<\/p>\n<p>II. CONSIDERACIONES Y FUNDAMENTOS \u00a0<\/p>\n<p>1. Competencia. \u00a0<\/p>\n<p>De \u00a0conformidad \u00a0con \u00a0lo \u00a0establecido en los \u00a0art\u00edculos \u00a086 \u00a0y 241-9 de la Constituci\u00f3n Pol\u00edtica y 31 a 36 del Decreto 2591 \u00a0de \u00a01991, \u00a0la \u00a0Corte \u00a0Constitucional \u00a0es \u00a0competente \u00a0para \u00a0revisar la decisi\u00f3n \u00a0judicial mencionada en precedencia. \u00a0\u00a0<\/p>\n<p>2. \u00a0 Planteamiento \u00a0del \u00a0caso \u00a0y \u00a0problema \u00a0jur\u00eddico. \u00a0\u00a0<\/p>\n<p>Corresponde \u00a0a \u00a0la \u00a0Sala \u00a0en \u00a0el \u00a0caso de la \u00a0referencia, \u00a0determinar si Seguro Social EPS y Nueva EPS han vulnerando o no los \u00a0derechos \u00a0a \u00a0la \u00a0vida, \u00a0a \u00a0la salud, a la seguridad social, al trabajo, al libre \u00a0desarrollo \u00a0 de \u00a0 la \u00a0 personalidad, \u00a0 a \u00a0 la \u00a0 igualdad \u00a0y \u00a0a \u00a0la \u00a0libertad \u00a0de \u00a0autodeterminaci\u00f3n \u00a0al \u00a0negarle \u00a0al \u00a0se\u00f1or \u00a0Roger \u00a0Rafael \u00a0Rambao Guti\u00e9rrez la \u00a0realizaci\u00f3n \u00a0de \u00a0la \u00a0cirug\u00eda de By Pass G\u00e1strico que necesita para superar la \u00a0Obesidad \u00a0 M\u00f3rbida \u00a0que \u00a0padece, \u00a0especialmente \u00a0porque \u00a0seg\u00fan \u00a0el \u00a0actor, \u00a0el \u00a0tratamiento \u00a0enunciado \u00a0le \u00a0ofrece \u00a0la posibilidad de mejorar su calidad de vida \u00a0ante \u00a0la \u00a0afectaci\u00f3n \u00a0f\u00edsica \u00a0y \u00a0psicol\u00f3gica que sufre. En este caso la Corte \u00a0Constitucional \u00a0deber\u00e1 \u00a0evaluar \u00a0si ha operado el fen\u00f3meno del hecho superado, \u00a0teniendo \u00a0en \u00a0cuenta \u00a0que \u00a0la \u00a0cirug\u00eda \u00a0de By Pass solicitado por el actor, fue \u00a0finalmente \u00a0autorizada y practicada seg\u00fan las pruebas aportadas en instancia de \u00a0revisi\u00f3n. \u00a0\u00a0<\/p>\n<p>Para \u00a0dar \u00a0soluci\u00f3n \u00a0al \u00a0problema jur\u00eddico \u00a0planteado, \u00a0la \u00a0Sala \u00a0deber\u00e1 \u00a0pronunciarse acerca de: (i) el fen\u00f3meno de hecho \u00a0superado \u00a0y \u00a0(ii) \u00a0la l\u00ednea \u00a0jurisprudencial \u00a0de \u00a0la \u00a0Corte \u00a0relacionada con el problema de salud p\u00fablica de \u00a0obesidad \u00a0m\u00f3rbida \u00a0y \u00a0la \u00a0autorizaci\u00f3n \u00a0de la cirug\u00eda bari\u00e1tica. Finalmente, \u00a0abordar\u00e1 el caso concreto. \u00a0\u00a0<\/p>\n<p>3. \u00a0 El \u00a0 fen\u00f3meno \u00a0del \u00a0hecho \u00a0superado. \u00a0Reiteraci\u00f3n de Jurisprudencia. \u00a0\u00a0<\/p>\n<p>3.1. \u00a0La Corte Constitucional ha considerado \u00a0que \u00a0en \u00a0aquellos \u00a0casos \u00a0en \u00a0los \u00a0que la aspiraci\u00f3n de un peticionario resulta \u00a0satisfecha \u00a0al momento de una decisi\u00f3n de tutela, y por ende ha desaparecido la \u00a0vulneraci\u00f3n \u00a0o amenaza de sus derechos fundamentales, la acci\u00f3n constitucional \u00a0pierde \u00a0su \u00a0eficacia \u00a0y \u00a0raz\u00f3n \u00a0de \u00a0ser, ante la extinci\u00f3n de los supuestos de \u00a0hecho \u00a0que \u00a0exig\u00edan \u00a0la \u00a0protecci\u00f3n \u00a0inminente \u00a0de \u00a0los derechos fundamentales \u00a0invocados20. \u00a0En tales casos, como la orden a impartir ser\u00eda inocua, en cuanto \u00a0a \u00a0los \u00a0posibles \u00a0efectos \u00a0que \u00a0pudiera\u00a0 \u00a0tener sobre la protecci\u00f3n de los \u00a0derechos \u00a0presuntamente conculcados, la tutela en principio resulta improcedente \u00a0en \u00a0raz\u00f3n \u00a0de \u00a0la \u00a0existencia \u00a0de un hecho superado21. \u00a0\u00a0<\/p>\n<p>3.2. \u00a0La \u00a0Corte \u00a0tambi\u00e9n ha manifestado que \u00a0cuando \u00a0un \u00a0hecho \u00a0superado \u00a0tiene lugar en sede de revisi\u00f3n, esta Corporaci\u00f3n \u00a0mantiene \u00a0su competencia para pronunciarse sobre la decisi\u00f3n del juez de tutela \u00a0en \u00a0 el \u00a0 caso \u00a0en \u00a0conocimiento, \u00a0a \u00a0fin \u00a0de \u00a0confirmar \u00a0o \u00a0revocar22 la decisi\u00f3n \u00a0proferida \u00a0por \u00a0los \u00a0jueces \u00a0de \u00a0instancia. \u00a0Esa \u00a0competencia \u00a0se \u00a0deriva \u00a0de la \u00a0obligaci\u00f3n \u00a0constitucional \u00a0que \u00a0tiene \u00a0la \u00a0Corte \u00a0de \u00a0revisar \u00a0los \u00a0fallos \u00a0de \u00a0instancia \u00a0 en \u00a0materia \u00a0de \u00a0tutela \u00a0y \u00a0de \u00a0su \u00a0responsabilidad \u00a0en \u00a0materia \u00a0de \u00a0unificaci\u00f3n \u00a0de \u00a0la \u00a0jurisprudencia \u00a0constitucional23. \u00a0 \u00a0As\u00ed, \u00a0 \u00a0existiendo \u00a0m\u00e9rito, \u00a0 este \u00a0Tribunal \u00a0puede \u00a0\u201crevocar \u00a0los \u00a0fallos \u00a0objeto \u00a0de \u00a0examen \u00a0y \u00a0conceder \u00a0 la \u00a0 tutela, \u00a0 sin \u00a0 importar \u00a0 que \u00a0 no \u00a0 proceda \u00a0 impartir \u00a0 orden \u00a0alguna\u201d24.\u00a0 \u00a0 En \u00a0 este \u00a0mismo \u00a0sentido, \u00a0el \u00a0art\u00edculo \u00a024 \u00a0del \u00a0Decreto \u00a02591 de 1991 establece que cuando cesen los efectos \u00a0del \u00a0acto impugnado o este se ha consumado, es posible prevenir a los accionados \u00a0para \u00a0que \u201cen ning\u00fan caso vuelvan a incurrir en las \u00a0acciones \u00a0u \u00a0omisiones \u00a0advertidas, \u00a0y \u00a0que, \u00a0si \u00a0procedieren \u00a0de modo contrario \u00a0ser\u00edan \u00a0sancionados, \u00a0en \u00a0los t\u00e9rminos de la misma disposici\u00f3n\u201d25. \u00a0\u00a0<\/p>\n<p>4. \u00a0L\u00ednea \u00a0jurisprudencial \u00a0en \u00a0torno \u00a0al \u00a0problema \u00a0 de \u00a0 salud \u00a0 p\u00fablica \u00a0que \u00a0representa \u00a0la \u00a0obesidad \u00a0m\u00f3rbida \u00a0y \u00a0la \u00a0autorizaci\u00f3n \u00a0por \u00a0parte \u00a0de \u00a0las \u00a0Entidades Promotoras de Salud de la cirug\u00eda \u00a0bari\u00e1trica \u00a0 \u2013By \u00a0Pass \u00a0g\u00e1strico-. \u00a0\u00a0<\/p>\n<p>4.1. \u00a0En \u00a0relaci\u00f3n \u00a0con la enfermedad de la \u00a0obesidad \u00a0m\u00f3rbida, \u00a0dolencia \u00a0que puede ser tratada a trav\u00e9s del procedimiento \u00a0quir\u00fargico \u00a0 de \u00a0 By \u00a0 Pass \u00a0 G\u00e1strico \u00a0 como \u00a0procedimiento \u00a0prescrito, \u00a0esta \u00a0Corporaci\u00f3n \u00a0 \u00a0 en \u00a0 \u00a0 diversas \u00a0 \u00a0oportunidades26 \u00a0 \u00a0ha \u00a0 \u00a0analizado \u00a0 \u00a0las \u00a0dificultades \u00a0que \u00a0para \u00a0la \u00a0salud \u00a0y calidad de vida de una persona ofrece esta \u00a0patolog\u00eda, por lo que ha autorizado su pr\u00e1ctica, as\u00ed: \u00a0\u00a0<\/p>\n<p>\u201cEn \u00a0sentencia \u00a0T-384 \u00a0de 200627 \u00a0 \u00a0la \u00a0Corte28 \u00a0sostuvo \u00a0que la obesidad m\u00f3rbida, \u201ces una enfermedad cr\u00f3nica y \u00a0progresiva, \u00a0vinculada \u00a0a numerosas enfermedades cr\u00f3nicas asociadas29, que llevan \u00a0a \u00a0 una \u00a0 prematura \u00a0incapacidad \u00a0y \u00a0mortalidad\u201d.30 \u00a0De \u00a0igual \u00a0manera \u00a0explic\u00f3 \u00a0que, \u00a0en \u00a0la \u00a0mayor\u00eda \u00a0de \u00a0los \u00a0casos \u00a0relacionados \u00a0con \u00a0esa dolencia \u201cse ha \u00a0demostrado \u00a0 que \u00a0 las \u00a0 terapias \u00a0 convencionales, \u00a0es \u00a0decir, \u00a0dietas, \u00a0drogas \u00a0antiobesidad \u00a0y el ejercicio f\u00edsico, son ineficaces en los obesos m\u00f3rbidos\u201d, \u00a0por \u00a0lo \u00a0que \u00a0la \u00a0cirug\u00eda \u00a0bari\u00e1trica, \u00a0&#8211; \u00a0como \u00a0procedimiento quir\u00fargico que \u00a0consiste \u00a0 \u201cen \u00a0 reducir, \u00a0mediante \u00a0distintas \u00a0t\u00e9cnicas \u00a0(principalmente \u00a0la \u00a0gastroplastia, \u00a0el \u00a0by \u00a0pass \u00a0g\u00e1strico \u00a0y \u00a0la banda ajustable) la capacidad del \u00a0est\u00f3mago\u201d-, \u00a0contribuye \u00a0a \u00a0mejorar \u00a0la \u00a0calidad \u00a0de vida de estas personas y \u00a0aumentar \u00a0 \u00a0 \u00a0su \u00a0 \u00a0 expectativa \u00a0 \u00a0 de \u00a0 \u00a0 vida31. \u00a0\u00a0<\/p>\n<p>Por \u00a0esta \u00a0raz\u00f3n, \u00a0en \u00a0la \u00a0providencia \u00a0en \u00a0menci\u00f3n, \u00a0esta \u00a0Corporaci\u00f3n arrib\u00f3 a la conclusi\u00f3n de que con la negativa de \u00a0la \u00a0Empresa \u00a0Promotora de Salud de autorizar esa clase de cirug\u00edas, no s\u00f3lo se \u00a0esta \u00a0 permitiendo \u00a0 que \u00a0 con \u00a0 el \u00a0tiempo \u00a0se \u00a0\u201cprolonguen \u00a0los \u00a0mencionados \u00a0padecimientos \u00a0colaterales\u201d o que \u201cpueda empeorar [el] cuadro cl\u00ednico\u201d de \u00a0las \u00a0personas \u00a0[que \u00a0la \u00a0sufren], sino que se \u201cagrav[e] su estado de salud por \u00a0las \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u2018comorbilidades\u2019\u201d \u00a0que \u00a0\u201cindudablemente \u00a0repercutir\u00e1n en su calidad de vida\u201d. \u00a0Por \u00a0ende, en tal oportunidad concluy\u00f3, que la negativa de la entidad accionada \u00a0de \u00a0conceder \u00a0la \u00a0cirug\u00eda \u00a0reclamada, \u00a0vulneraba \u00a0efectivamente el derecho a la \u00a0salud \u00a0en \u00a0conexidad \u00a0con \u00a0la \u00a0vida \u00a0de \u00a0la persona, por lo que al cumplirse los \u00a0requisitos \u00a0constitucionales \u00a0para \u00a0la \u00a0autorizaci\u00f3n de tratamientos no POS por \u00a0v\u00eda \u00a0de \u00a0tutela, \u00a0la \u00a0EPS \u00a0accionada \u00a0deb\u00eda \u00a0realizar \u00a0la cirug\u00eda bari\u00e1trica \u00a0prescrita, \u00a0 \u00a0a \u00a0 \u00a0favor \u00a0 \u00a0de \u00a0 \u00a0la \u00a0 \u00a0demandante32. \u00a0\u00a0<\/p>\n<p>Posteriormente, \u00a0en \u00a0la \u00a0Sentencia \u00a0T-725 de \u00a02007, \u00a0la \u00a0Corte \u00a0precis\u00f3 \u00a0y \u00a0unific\u00f3 \u00a0las \u00a0condiciones necesarias para que la \u00a0cirug\u00eda \u00a0bariatica pudiese ser autorizada por v\u00eda de tutela cuando dispuso que \u00a0para \u00a0su procedencia se deb\u00edan cumplir con los siguientes requisitos: i) deb\u00eda \u00a0quedar \u00a0plenamente \u00a0demostrado \u00a0que \u00a0la \u00a0persona \u00a0ten\u00eda \u00a0una \u00a0patolog\u00eda que le \u00a0imped\u00eda \u00a0 absolutamente \u00a0 desenvolverse \u00a0 en \u00a0comunidad \u00a0o \u00a0que \u00a0ten\u00eda \u00a0graves \u00a0consecuencias \u00a0para \u00a0su \u00a0vida \u00a0biol\u00f3gica, \u00a0\u201cincluso \u00a0la \u00a0existencia misma del \u00a0afectado\u201d33; \u00a0ii) \u00a0deb\u00eda \u00a0demostrarse \u00a0que \u00a0el \u00a0diagn\u00f3stico \u00a0y \u00a0solicitud \u00a0de \u00a0pr\u00e1ctica \u00a0del procedimiento hab\u00edan sido proferidos por los m\u00e9dicos vinculados \u00a0a \u00a0la \u00a0EPS \u00a0accionada; \u00a0iii) \u00a0adem\u00e1s, \u00a0deb\u00eda \u00a0acreditarse que no exist\u00eda otro \u00a0tratamiento \u00a0capaz\u00a0 \u00a0de \u00a0evitar \u00a0el \u00a0da\u00f1o \u00a0a la vida; y, iv) deb\u00eda quedar \u00a0claro \u00a0que \u00a0la \u00a0persona \u00a0no \u00a0contaba \u00a0con los medios econ\u00f3micos necesarios para \u00a0sufragar \u00a0el \u00a0tratamiento, \u00a0bien \u00a0sea \u00a0directamente o por medio de mecanismos de \u00a0financiaci\u00f3n \u00a0 \u00a0no \u00a0 \u00a0confiscatorios \u00a0 \u00a0que \u00a0 \u00a0cubran \u00a0 el \u00a0 riesgo34\u201d.35 \u00a0\u00a0<\/p>\n<p>En \u00a0las sentencias citadas para autorizar el \u00a0procedimiento \u00a0quir\u00fargico \u00a0del \u00a0By Pass G\u00e1strico se exigi\u00f3 el cumplimiento de \u00a0unos \u00a0requisitos, que son b\u00e1sicamente los se\u00f1alados por esta Corporaci\u00f3n para \u00a0inaplicar \u00a0las \u00a0normas \u00a0que \u00a0regulan \u00a0las \u00a0exclusiones \u00a0de prestaciones del POS. \u00a0\u00a0<\/p>\n<p>4.2. \u00a0Sin \u00a0embargo \u00a0la \u00a0Corte, \u00a0al \u00a0realizar \u00a0recientemente \u00a0un \u00a0estudio sobre la problem\u00e1tica de salud p\u00fablica en relaci\u00f3n \u00a0con \u00a0la \u00a0obesidad m\u00f3rbida y su tratamiento a trav\u00e9s de la cirug\u00eda bari\u00e1trica \u00a0en \u00a0su especialidad de By Pass g\u00e1strico, sostuvo en sentencia T-414 de 2008 que \u00a0dichos \u00a0procedimientos \u00a0deben \u00a0entenderse \u00a0como \u00a0incluidos \u00a0dentro \u00a0del \u00a0POS. Lo \u00a0anterior \u00a0en \u00a0raz\u00f3n \u00a0de que el art\u00edculo 62 de la Resoluci\u00f3n No. 5261 de 1994, \u00a0que \u00a0regula el Plan Obligatorio de Salud del R\u00e9gimen Contributivo, contempla la \u00a0\u201cDERIVACIONES \u00a0 \u00a0 DE \u00a0 \u00a0EST\u00d3MAGO\u201d \u00a0bajo el c\u00f3digo 07631 y que si bien dentro de esa denominaci\u00f3n no \u00a0se \u00a0 \u00a0incluye \u00a0 \u00a0en \u00a0 ninguno \u00a0 de \u00a0 sus \u00a0 apartes \u00a0 la \u00a0 palabra \u00a0 \u201ccirug\u00eda \u00a0 \u00a0 bari\u00e1trica\u201d, \u00a0 \u00a0 ni \u00a0la\u201ccirug\u00eda \u00a0 By \u00a0 Pass \u00a0 g\u00e1strico\u201d, \u00a0si \u00a0se \u00a0hace \u00a0referencia al siguiente procedimiento: \u201cAnastomosis \u00a0del \u00a0est\u00f3mago; \u00a0incluye gatroduodenostom\u00eda con el \u00a0c\u00f3digo 07630 y Anastomosis en Y de Roux C\u00f3digo 07631\u201d. \u00a0\u00a0<\/p>\n<p>\u201cLa resoluci\u00f3n 5261 de 1994, que establece \u00a0las \u00a0actividades, intervenciones y procedimientos del Plan Obligatorio de Salud, \u00a0no \u00a0expresa \u00a0taxativamente \u00a0el procedimiento utilizando la expresi\u00f3n inglesa de \u00a0By-pass \u00a0g\u00e1strico \u00a0pero \u00a0s\u00ed \u00a0estableci\u00f3 en su ART\u00cdCULO 62 las intervenciones \u00a0quir\u00fargicas \u00a0abdominales \u00a0que \u00a0como \u00a0t\u00e9cnicas \u00a0quir\u00fargicas \u00a0se \u00a0utilizan para \u00a0realizar la derivaci\u00f3n de estomago, como\u00a0 son: \u00a0\u00a0<\/p>\n<p>Anastomosis \u00a0 del \u00a0 est\u00f3mago; \u00a0 incluye \u00a0gatroduodenostom\u00eda con el c\u00f3digo 07630 \u00a0\u00a0<\/p>\n<p>Anastomosis \u00a0del \u00a0est\u00f3mago \u00a0en \u00a0Y \u00a0de \u00a0Roux \u00a0C\u00f3digo 07631. \u00a0\u00a0<\/p>\n<p>\u201cProcedimiento \u00a0que, \u00a0como ya se mencion\u00f3 \u00a0anteriormente, \u00a0 \u00a0 SON \u00a0 \u00a0LOS \u00a0 \u00a0QUE \u00a0 \u00a0SE \u00a0 \u00a0UTILIZAN \u00a0 \u00a0EN \u00a0 \u00a0EL \u00a0 \u00a0BY \u00a0 \u00a0PASS \u00a0G\u00c1STRICO&#8230;\u201d \u00a0\u00a0<\/p>\n<p>4.3. \u00a0En \u00a0suma, \u00a0esta Corporaci\u00f3n en varias \u00a0sentencias, \u00a0entre \u00a0ellas \u00a0la \u00a0T-414 de 2008, sostuvo que la cirug\u00eda de By Pass \u00a0G\u00e1strico, \u00a0para la reducci\u00f3n de peso y masa corporal, necesaria para tratar la \u00a0patolog\u00eda \u00a0de \u00a0obesidad m\u00f3rbida, est\u00e1 incluida dentro del Plan Obligatorio de \u00a0Salud \u00a0del \u00a0R\u00e9gimen contributivo, bajo una denominaci\u00f3n diferente, tal como lo \u00a0expuso \u00a0el \u00a0Instituto \u00a0Nacional \u00a0de\u00a0 Medicina \u00a0 Legal \u00a0y \u00a0Ciencias \u00a0Forenses36. \u00a0En \u00a0ese \u00a0orden \u00a0de \u00a0ideas, \u00a0se\u00f1al\u00f3 \u00a0que \u00a0las \u00a0Entidades \u00a0Promotoras de Salud deben cubrir la totalidad del \u00a0costo \u00a0de \u00a0la \u00a0cirug\u00eda \u00a0bari\u00e1trica, en los pacientes con obesidad m\u00f3rbida que \u00a0as\u00ed \u00a0 lo \u00a0 requieran, \u00a0 siempre \u00a0y \u00a0cuando \u00a0el \u00a0m\u00e9dico \u00a0tratante \u00a0y \u00a0un \u00a0grupo \u00a0interdisciplinario \u00a0de \u00a0galenos \u00a0as\u00ed lo dictaminen. Se requiere igualmente, que \u00a0el paciente d\u00e9 su consentimiento informado. \u00a0\u00a0<\/p>\n<p>4.4. En consecuencia, si en sede de tutela se \u00a0reclama \u00a0 la \u00a0 autorizaci\u00f3n \u00a0 de \u00a0 la \u00a0cirug\u00eda \u00a0By \u00a0Pass \u00a0g\u00e1strico \u00a0(cirug\u00eda \u00a0bari\u00e1trica), \u00a0ante \u00a0la \u00a0negativa \u00a0de \u00a0las \u00a0Entidades \u00a0Promotoras \u00a0de \u00a0Salud \u00a0de \u00a0realizarlo, \u00a0el \u00a0juez \u00a0de \u00a0tutela debe ordenar su pr\u00e1ctica con cargo total a la \u00a0Entidad \u00a0Promotora \u00a0de \u00a0Salud \u00a0Accionada sin, la posibilidad de repetir al fondo \u00a0Nacional \u00a0de \u00a0Solidaridad \u00a0-FOSYGA-, \u00a0por \u00a0estar dicho procedimiento quir\u00fargico \u00a0incluido en el Plan Obligatorio de Salud. \u00a0\u00a0<\/p>\n<p>4.5. Por otro lado, la jurisprudencia de esta \u00a0Corporaci\u00f3n, \u00a0dada \u00a0la peligrosidad de este procedimiento, tambi\u00e9n estableci\u00f3 \u00a0que \u00a0para que se de el procedimiento quir\u00fargico del By Pass G\u00e1strico se deb\u00eda \u00a0obtener \u00a0 \u00a0el \u00a0 \u00a0\u201cconsentimiento \u00a0 informado \u00a0 del \u00a0paciente\u201d37, \u00a0as\u00ed \u00a0como \u00a0tener \u00a0la \u00a0valoraci\u00f3n t\u00e9cnica realizada al paciente \u00a0\u201ccandidato\u201d \u00a0 de \u00a0 la \u00a0cirug\u00eda, \u00a0por parte de \u201cun grupo interdisciplinario \u00a0de \u00a0m\u00e9dicos\u201d, \u00a0realizada antes de la emisi\u00f3n de la \u00a0orden \u00a0m\u00e9dica \u00a0en \u00a0el que se le prescriba\u00a0 dicho procedimiento38. \u00a0\u00a0<\/p>\n<p>\u201c11. Debe recordarse, en este punto, que la \u00a0Corporaci\u00f3n, \u00a0debido \u00a0a \u00a0la \u00a0complejidad \u00a0y al riesgo quir\u00fargico que supone el \u00a0procedimiento \u00a0gen\u00e9ricamente \u00a0descrito, ha sido enf\u00e1tica en exigir el especial \u00a0cumplimiento \u00a0de \u00a0dos \u00a0requisitos \u00a0particulares: \u00a0(i) \u00a0la \u00a0efectiva \u00a0valoraci\u00f3n \u00a0t\u00e9cnica \u00a0 que \u00a0 debe \u00a0 hacerse, \u00a0 en \u00a0 cada \u00a0 caso \u00a0particular, \u00a0por \u00a0un \u00a0grupo \u00a0interdisciplinario \u00a0de \u00a0m\u00e9dicos, \u00a0la cual debe preceder a la orden de pr\u00e1ctica \u00a0del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 procedimiento39; y (ii) el \u201cconsentimiento \u00a0informado \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del \u00a0 \u00a0 \u00a0 \u00a0 \u00a0paciente\u201d40,\u00a0 \u00a0que \u00a0consiste \u00a0en el \u00a0deber \u00a0que \u00a0asiste \u00a0a \u00a0los profesionales de la ciencias m\u00e9dicas de informar, en \u00a0forma \u00a0clara \u00a0y \u00a0concreta, los efectos del procedimiento que el paciente se va a \u00a0practicar, \u00a0para \u00a0que \u00a0manifieste \u00a0de \u00a0manera libre y espont\u00e1nea su voluntad de \u00a0someterse al mismo. \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>En \u00a0efecto, \u00a0para \u00a0el \u00a0caso \u00a0particular \u00a0del \u00a0procedimiento \u00a0de \u201cBy Pass g\u00e1strico por laparoscopia\u201d, esta Corporaci\u00f3n ha \u00a0se\u00f1alado \u00a0que, \u00a0\u201cen \u00a0la medida en que la accionante requiere de la mencionada \u00a0cirug\u00eda \u00a0para solucionar su problema de sobrepeso que est\u00e1 afectando de manera \u00a0grave \u00a0su \u00a0salud \u00a0y \u00a0que \u00a0atenta \u00a0igualmente \u00a0en \u00a0contra \u00a0de \u00a0su \u00a0vida, \u00a0resulta \u00a0importante, \u00a0 que \u00a0 previo \u00a0 a \u00a0la \u00a0realizaci\u00f3n \u00a0del \u00a0mencionado \u00a0procedimiento \u00a0quir\u00fargico, \u00a0y \u00a0de \u00a0que \u00a0la \u00a0accionante \u00a0d\u00e9 \u00a0su \u00a0consentimiento para el mismo, \u00a0obtenga \u00a0de \u00a0todos \u00a0y \u00a0cada \u00a0uno de los m\u00e9dicos especialistas que de una u otra \u00a0forma \u00a0tengan \u00a0dentro de su conocimiento el manejo, tratamiento y control de las \u00a0otras \u00a0patolog\u00edas \u00a0que \u00a0le han sido diagnosticadas y que aparecen rese\u00f1adas en \u00a0el \u00a0\u00faltimo control m\u00e9dico, la informaci\u00f3n necesaria acerca de los efectos que \u00a0dicho \u00a0procedimiento quir\u00fargico tendr\u00eda en relaci\u00f3n con esas afecciones. Ello \u00a0con \u00a0el \u00a0fin \u00a0de \u00a0que, estando plenamente informada la paciente, pueda de manera \u00a0libre \u00a0y \u00a0espont\u00e1nea \u00a0dar \u00a0su \u00a0consentimiento \u00a0y autorizar le sea practicada la \u00a0anotada \u00a0 cirug\u00eda \u00a0 de \u00a0 BY \u00a0 PASS \u00a0 G\u00c1STRICO.\u201d41\u00a0\u00a0 \u00a0 (negrilla \u00a0 y \u00a0subrayado adicionado) \u00a0\u00a0<\/p>\n<p>5. \u00a0Caso \u00a0Concreto. \u00a0Existencia de un hecho \u00a0superado \u00a0\u00a0<\/p>\n<p>5.1. \u00a0De \u00a0las \u00a0pruebas \u00a0que \u00a0obran \u00a0en \u00a0el \u00a0expediente, \u00a0practicadas \u00a0en \u00a0sede \u00a0de \u00a0revisi\u00f3n, \u00a0se \u00a0puede \u00a0establecer que la \u00a0cirug\u00eda \u00a0del \u00a0By \u00a0Pass \u00a0G\u00e1strico \u00a0solicitada por el se\u00f1or Roger Rafael Rambao \u00a0Guti\u00e9rrez \u00a0le fue ordenada y practicada por su m\u00e9dico tratante, quien mediante \u00a0escrito \u00a0fechado \u00a020 \u00a0de \u00a0febrero \u00a0manifest\u00f3 que la cirug\u00eda bari\u00e1trica le fue \u00a0practicada \u00a0al accionante el d\u00eda 29 de enero del a\u00f1o en curso, a trav\u00e9s de la \u00a0Nueva \u00a0EPS, \u00a0una \u00a0vez \u00a0autoriz\u00f3 \u00a0el \u00a0procedimiento. \u00a0En \u00a0el \u00a0presente \u00a0caso, en \u00a0consecuencia, se declarar\u00e1 la existencia de un hecho superado. \u00a0\u00a0<\/p>\n<p>5.2. Sin embargo, es preciso resaltar que no \u00a0se \u00a0puede \u00a0exigir \u00a0a \u00a0los \u00a0usuarios \u00a0del \u00a0Sistema General de Seguridad Social en \u00a0Salud, \u00a0que \u00a0solicitan \u00a0el suministro de medicamentos o procedimientos excluidos \u00a0del \u00a0 POS \u00a0acudir \u00a0previamente \u00a0al \u00a0Comit\u00e9 \u00a0T\u00e9cnico \u00a0Cient\u00edfico \u00a0\u2013CTC-, como requisito de procedencia de \u00a0la \u00a0 acci\u00f3n \u00a0 de \u00a0 tutela \u00a0 y \u00a0 mucho \u00a0 menos \u00a0 para \u00a0 acceder \u00a0a \u00a0un \u00a0servicio \u00a0m\u00e9dico42 \u00a0\u00a0<\/p>\n<p>. Por otro lado, si la cirug\u00eda bari\u00e1tria, \u00a0como \u00a0lo ha reiterado la jurisprudencia de esta Corporaci\u00f3n se encuentra dentro \u00a0del \u00a0POS, \u00a0ni \u00a0siquiera \u00a0es \u00a0un \u00a0requisito \u00a0administrativo que la orden de dicha \u00a0cirug\u00eda sea evaluada por el Comit\u00e9 T\u00e9cnico Cient\u00edfico. \u00a0\u00a0<\/p>\n<p>5.3. \u00a0Dado que al actor ya se le reconoci\u00f3 \u00a0su \u00a0derecho a la salud, la presente acci\u00f3n como instrumento constitucional para \u00a0la \u00a0defensa de los derechos fundamentales del ciudadano perdi\u00f3 su raz\u00f3n de ser \u00a0y \u00a0los \u00a0motivos \u00a0que \u00a0llevaron a interponer la acci\u00f3n de tutela desaparecieron, \u00a0por \u00a0lo \u00a0que \u00a0la \u00a0Sala \u00a0revocar\u00e1 \u00a0el \u00a0fallo \u00a0proferido el 8 de mayo de 2008 por \u00a0Juzgado \u00a0Penal \u00a0del \u00a0Circuito \u00a0de \u00a0Soledad, por las consideraciones expuestas en \u00a0esta providencia. \u00a0\u00a0<\/p>\n<p>III. DECISI\u00d3N. \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Quinta de \u00a0Revisi\u00f3n \u00a0de \u00a0la \u00a0Corte \u00a0Constitucional, \u00a0administrando \u00a0justicia en nombre del \u00a0pueblo y por mandato de la Constituci\u00f3n, \u00a0\u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>Primero. \u00a0DECLARAR \u00a0la existencia de un hecho superado. \u00a0\u00a0<\/p>\n<p>Segundo. REVOCAR la \u00a0sentencia \u00a0del \u00a08 de mayo de 2008 por Juzgado Penal del Circuito de Soledad, por \u00a0las consideraciones expuestas en esta providencia. \u00a0\u00a0<\/p>\n<p>Tercero. \u00a0Por \u00a0 \u00a0 Secretar\u00eda, \u00a0l\u00edbrese \u00a0la comunicaci\u00f3n prevista en el art\u00edculo 36 \u00a0del Decreto 2591 de 1991. \u00a0\u00a0<\/p>\n<p>Notif\u00edquese, \u00a0comun\u00edquese, publ\u00edquese en \u00a0la Gaceta de la Corte Constitucional y c\u00famplase. \u00a0\u00a0<\/p>\n<p>MAURICIO GONZ\u00c1LEZ CUERVO \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>CRISTINA PARDO SCHLESINGER (E) \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>NILSON PINILLA PINILLA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0<\/p>\n<p>Secretaria General \u00a0<\/p>\n<p>1 Ver \u00a0folios 24 a 28 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>2 Quien \u00a0cuenta \u00a0con 54 a\u00f1os de edad \u201cnaci\u00f3 el 17 de febrero de 1954\u201d. Ver historia \u00a0cl\u00ednica folios 12 y 13 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>3 Ver \u00a0acci\u00f3n de tutela, folios 1 a 6 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>4 Ver \u00a0folio 22 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>5 Ver \u00a0historias \u00a0cl\u00ednicas, fechadas del 20 de diciembre de 2007 y del 8 de febrero de \u00a02008, \u00a0en \u00a0donde \u00a0se \u00a0constata: \u00a0el \u00a0diagn\u00f3stico del se\u00f1or Roger Rafael Rambao \u00a0Guti\u00e9rrez, \u00a0\u201cOBESIDAD EXTREMA CON HIPOVENTILACI\u00d3N \u00a0ALVEOLAR\u201d, \u00a0es \u00a0decir \u00a0un sobrepeso considerable y, \u00a0las \u00a0dificultades \u00a0que como consecuencia de \u00e9sta ha venido presentando, a saber \u00a0\u201cDIFICULTAD \u00a0PARA \u00a0CAMINAR \u00a0DOLOR \u00a0EN \u00a0LA \u00a0RODILLA \u00a0DERECHA, \u00a0ESPALDA, \u00a0CUELLO \u00a0Y \u00a0TALONES\u201d. \u00a0De \u00a0igual \u00a0manera \u00a0se indica que el accionante \u201cSE ENCUENTRA EN \u00a0PROGRAMACI\u00d3N \u00a0DE \u00a0CX BARI\u00c1TRICA\u201d. Ver folios 12-13 \u00a0y 16 del cuaderno\u00a0 \u00a0\u00a0<\/p>\n<p>6 \u00a0Doctor Pedro Trillos Franco. Ver folio del Cuaderno #1. \u00a0\u00a0<\/p>\n<p>7 Ver \u00a0historia cl\u00ednica folios 16 y 17 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>8 Ver \u00a0folio 9 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>9 Ver \u00a0Historia Cl\u00ednica folios 12 y 13 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>10 Ver \u00a0folio 7 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>11 \u00a0Remisi\u00f3n a cirug\u00eda general, previo a la cirug\u00eda bari\u00e1trica. \u00a0\u00a0<\/p>\n<p>12 Ver \u00a0folios 10 y 11 cuaderno #1. \u00a0\u00a0<\/p>\n<p>13 \u00a0\u201cdonde \u00a0solicita Junta M\u00e9dica para evaluar su estado de Obesidad M\u00f3rbida con \u00a0Riesgo Metab\u00f3lico\u201d. \u00a0\u00a0<\/p>\n<p>14 Ver \u00a0acci\u00f3n de tutela, folios 1 a 6 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>15 \u00a0Esto \u00a0lo \u00a0deduce \u00a0del \u00a0contenido \u00a0de \u00a0la \u00a0respuesta \u00a0dada\u00a0 \u00a0a \u00a0la petici\u00f3n \u00a0presentada \u00a0por el actor y el de que a pesar de expresar que aporta solicitud en \u00a0este sentido como prueba no se encuentra anexa al expediente. \u00a0\u00a0<\/p>\n<p>16 Ver \u00a0folio 8 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>17 Ver \u00a0folios 31 a 32 del cuaderno #1. \u00a0\u00a0<\/p>\n<p>18 Con \u00a0fundamento \u00a0en \u00a0los \u00a0Decretos\u00a0 \u00a0055 \u00a0de \u00a02007, \u00a02713 \u00a0de \u00a0200 \u00a0y \u00a0el 781 de \u00a02008. \u00a0\u00a0<\/p>\n<p>19 Ver \u00a0folios 13 y 14 cuaderno principal. \u00a0\u00a0<\/p>\n<p>20 \u00a0Sentencia T-519 de 1992. M.P. Jos\u00e9 Gregorio Hern\u00e1ndez Galindo \u00a0\u00a0<\/p>\n<p>21 \u00a0Sentencia T-100 de 1995. M.P. Vladimiro Naranjo Mesa. \u00a0\u00a0<\/p>\n<p>22 \u00a0Sentencia T-550 de 2005. M.P. Jaime Araujo Renter\u00eda. \u00a0\u00a0<\/p>\n<p>23 \u00a0Sentencia T-673 de 2000. M.P. Alejandro Mart\u00ednez Caballero. \u00a0\u00a0<\/p>\n<p>24 \u00a0Sentencia T-724 de 2003. M.P. Jaime Araujo Renter\u00eda. \u00a0\u00a0<\/p>\n<p>25 \u00a0Sentencia T-1035 de 2006 M.P. Humberto Sierra Porto. \u00a0\u00a0<\/p>\n<p>26 \u00a0Corte \u00a0Constitucional. Sentencias T-867 de 2006 M.P. Marco Gerardo Monroy Cabra, \u00a0T-469 \u00a0de 2006 M.P. Humberto Sierra Porto, T-384 de 2006 M.P. Clara In\u00e9s Vargas \u00a0Hern\u00e1ndez, \u00a0T-265 \u00a0de \u00a02006 \u00a0M.P. \u00a0Jaime \u00a0Araujo \u00a0Renter\u00eda, T-060 de 2006 M.P. \u00a0\u00c1lvaro \u00a0Tafur \u00a0Galvis, \u00a0T-027 \u00a0de \u00a02006 M.P. Alfredo Beltr\u00e1n Sierra, T-1272 de \u00a02005 \u00a0M.P. \u00a0Rodrigo \u00a0Escobar \u00a0Gil, \u00a0T-1229 \u00a0de 2005 M.P. Jaime Araujo Renter\u00eda, \u00a0T-828 \u00a0 de \u00a0 2005 \u00a0 M.P. \u00a0 Humberto \u00a0 Sierra \u00a0 Porto \u00a0y \u00a0T-264 \u00a0de \u00a02003, \u00a0entre \u00a0otras. \u00a0\u00a0<\/p>\n<p>27 \u00a0M.P. Clara In\u00e9s Vargas Hern\u00e1ndez. \u00a0\u00a0<\/p>\n<p>28 Se \u00a0trat\u00f3 \u00a0del \u00a0caso \u00a0de \u00a0una \u00a0paciente \u00a0a \u00a0quien \u00a0la \u00a0EPS Seguro Social se neg\u00f3 a \u00a0autorizar \u00a0y realizar la cirug\u00eda bari\u00e1trica que le fue ordenada por su m\u00e9dico \u00a0tratante, \u00a0para \u00a0contrarrestar la Obesidad M\u00f3rbida G3. Esa enfermedad le hab\u00eda \u00a0causado \u00a0dolencias \u00a0colaterales, \u00a0como \u00a0problemas \u00a0de \u00a0columna, ahogo nocturno y \u00a0dolor \u00a0en \u00a0la \u00a0cintura \u00a0y \u00a0pies \u00a0que \u00a0compromet\u00edan \u00a0las funciones vitales de la \u00a0actora. \u00a0La \u00a0Corte \u00a0consider\u00f3 \u00a0en \u00a0ese \u00a0caso, \u00a0que \u00a0dado \u00a0que \u00a0se cumpl\u00edan los \u00a0requisitos \u00a0\u201cexigidos por la jurisprudencia de esta Corporaci\u00f3n para proteger \u00a0los \u00a0derechos \u00a0a \u00a0la \u00a0vida, a la salud y a la dignidad humana\u201d de la actora, y \u00a0por \u00a0tanto \u00a0orden\u00f3 que la EPS ISS Seccional Cundinamarca dentro de las 48 horas \u00a0siguientes \u00a0a \u00a0la notificaci\u00f3n del fallo, si a\u00fan no lo hab\u00eda hecho autorizara \u00a0y practicara la CIRUG\u00cdA BARI\u00c1TRICA. \u00a0\u00a0<\/p>\n<p>29 \u00a0Entre \u00a0otras \u00a0seg\u00fan \u00a0la \u00a0sentencia, \u00a0\u201cEnfermedad \u00a0cardiovascular, de arterias \u00a0coronarias, \u00a0s\u00edndrome \u00a0de \u00a0apnea \u00a0del \u00a0sue\u00f1o, \u00a0h\u00edgado \u00a0graso, \u00a0osteoartritis, \u00a0dislipidemia, \u00a0intolerancia a la glucosa o diabetes, hiperuricemia, alteraciones \u00a0menstruales, \u00a0infertilidad \u00a0y \u00a0mayor \u00a0frecuencia \u00a0de c\u00e1ncer de mama y ovario (3 \u00a0veces), \u00fatero (5 veces), colon y pr\u00f3stata (3 veces)\u201d. \u00a0\u00a0<\/p>\n<p>30 De \u00a0hecho, \u00a0esta \u00a0providencia \u00a0sostuvo, \u00a0que \u201cpruebas cient\u00edficas han determinado \u00a0que \u00a0las \u00a0personas \u00a0con \u00a0un \u00a0diagnostico \u00a0de \u00a0obesidad m\u00f3rbida tienen una menor \u00a0expectativa de vida (10-15 a\u00f1os) y mayor mortalidad (6-12 veces). \u00a0\u00a0<\/p>\n<p>31 \u00a0Cfr. Sentencia T-384 de 2006. M.P. Clara In\u00e9s Vargas Hern\u00e1ndez. \u00a0\u00a0<\/p>\n<p>32 \u00a0Sobre \u00a0el \u00a0particular, \u00a0puede \u00a0consultarse igualmente la sentencia T-171 de 2003 \u00a0(M.P. \u00a0Rodrigo \u00a0Escobar Gil), en la que se analiz\u00f3 un caso de obesidad m\u00f3rbida \u00a0relacionado \u00a0con la negativa de una empresa de medicina prepagada de realizar la \u00a0operaci\u00f3n \u00a0bari\u00e1trica correspondiente. En ese caso se le orden\u00f3 al particular \u00a0la \u00a0realizaci\u00f3n \u00a0de \u00a0la \u00a0cirug\u00eda. \u00a0En \u00a0la \u00a0sentencia T-264 de 2003 (M.P. Jaime \u00a0C\u00f3rdoba \u00a0Trivi\u00f1o) \u00a0se \u00a0estudi\u00f3 \u00a0una \u00a0situaci\u00f3n \u00a0en \u00a0la \u00a0que \u00a0no era claro el \u00a0beneficio \u00a0del \u00a0By \u00a0Pass \u00a0G\u00e1strico \u00a0para \u00a0la paciente, por lo que se orden\u00f3 su \u00a0valoraci\u00f3n \u00a0por parte de un equipo interdisciplinario que revisara la necesidad \u00a0y \u00a0oportunidad \u00a0para la actora de la cirug\u00eda bari\u00e1trica y en caso de que fuera \u00a0conducente, \u00a0que \u00a0se \u00a0practicara. \u00a0En \u00a0la \u00a0sentencia \u00a0T-1229 de 2005 (M.P. Jaime \u00a0Araujo \u00a0Renter\u00eda) \u00a0se \u00a0analiz\u00f3 \u00a0el \u00a0caso de una paciente con obesidad m\u00f3rbida \u00a0perteneciente \u00a0al \u00a0Sisben y sin capacidad econ\u00f3mica para cubrir el copago de la \u00a0cirug\u00eda \u00a0de \u00a0By \u00a0Pass. \u00a0En esa sentencia, a pesar de que los m\u00e9dicos tratantes \u00a0hab\u00edan \u00a0enunciado \u00a0que la se\u00f1ora era \u201ccandidata\u201d a la cirug\u00eda de By Pass, \u00a0la \u00a0Corte \u00a0orden\u00f3 \u00a0a la Secretar\u00eda Distrital de Salud de Bogot\u00e1 contratar con \u00a0alguna \u00a0entidad \u00a0especializada la realizaci\u00f3n de la cirug\u00eda, previa obtenci\u00f3n \u00a0de \u00a0un \u00a0consentimiento \u00a0informado de la paciente. En esa providencia adem\u00e1s, se \u00a0record\u00f3 \u00a0la necesidad de lograr un consentimiento informado, dado que este tipo \u00a0de \u00a0cirug\u00edas \u00a0son \u00a0altamente \u00a0invasivas \u00a0y \u00a0presentan en algunos casos, efectos \u00a0secundarios. \u00a0Ver \u00a0tambi\u00e9n la sentencia T-060 de 2006 M.P. \u00c1lvaro Tafur Galvis \u00a0en \u00a0la \u00a0que \u00a0se \u00a0sigui\u00f3 \u00a0esta \u00a0misma \u00a0l\u00ednea \u00a0jurisprudencial y se concedi\u00f3 la \u00a0tutela. \u00a0\u00a0<\/p>\n<p>33 \u00a0Sentencia, T-110 de 2007. \u00a0\u00a0<\/p>\n<p>34 \u00a0Reiterada en la sentencia T-586 de 2008. \u00a0\u00a0<\/p>\n<p>35 \u00a0Sentencia T-193 de 2008, M.P. Mauricio Gonz\u00e1lez Cuervo. \u00a0\u00a0<\/p>\n<p>36 En \u00a0dicho fallo la Sala de Revisi\u00f3n aclar\u00f3: \u00a0\u00a0<\/p>\n<p>\u201cSin embargo, en cada \u00a0caso \u00a0concreto, \u00a0ser\u00e1 el m\u00e9dico tratante y el grupo interdisciplinario los que \u00a0determinen \u00a0el \u00a0tratamiento, \u00a0medicamentos \u00a0y \u00a0procedimientos \u00a0indicados \u00a0e cada \u00a0paciente \u00a0para \u00a0el \u00a0manejo \u00a0de \u00a0su \u00a0obesidad, \u00a0con \u00a0su respectivo consentimiento \u00a0informado \u00a0 y \u00a0 respeto \u00a0 del \u00a0 derecho \u00a0 al \u00a0 diagn\u00f3stico \u00a0 como \u00a0ya \u00a0se\u00a0 \u00a0se\u00f1al\u00f3. \u00a0\u00a0<\/p>\n<p>Para \u00a0finalizar, \u00a0en \u00a0lo \u00a0que respecta a la \u00a0tercera \u00a0pregunta \u00a0que \u00a0trata \u00a0sobre \u00a0lo \u00a0descrito \u00a0en \u00a0el \u00a0art\u00edculo \u00a062 \u00a0de la \u00a0Resoluci\u00f3n \u00a05261 \u00a0de \u00a01994, \u00a0que \u00a0hace \u00a0referencia \u00a0a \u00a0las \u00a0\u201cDERIVACIONES \u00a0EN \u00a0EST\u00d3MAGO\u201d \u00a0bajo \u00a0el \u00a0C\u00f3digo \u00a007630 \u00a0Anastomosis \u00a0del \u00a0est\u00f3mago; \u00a0incluyendo \u00a0gastroyeyunostom\u00eda \u00a0y el C\u00f3digo 07631 Anastomosis de \u00a0est\u00f3mago \u00a0en \u00a0Y \u00a0de \u00a0Roux, \u00a0conforme \u00a0a \u00a0los dict\u00e1menes solicitados pueden ser \u00a0entendidas \u00a0t\u00e9cnicamente \u00a0como el procedimiento gen\u00e9ricamente descrito como By \u00a0pass \u00a0 g\u00e1strico \u00a0 para \u00a0 cirug\u00eda \u00a0 bari\u00e1tica&#8230;\u201d\u00a0\u00a0 \u00a0 (negrilla y subraya fuera de texto) \u00a0\u00a0<\/p>\n<p>37 \u00a0Requisito que ya hab\u00eda introducido la Sentencia T-1229 de 2005. \u00a0\u00a0<\/p>\n<p>38 \u00a0Sentencia T-725 de 2007 \u00a0\u00a0<\/p>\n<p>39 \u00a0Ante \u00a0el \u00a0caso \u00a0an\u00e1logo de paciente con diagn\u00f3stico de obesidad m\u00f3rbida grado \u00a0III, \u00a0esta \u00a0Corporaci\u00f3n \u00a0tras \u00a0estudiar \u00a0la \u00a0historia \u00a0cl\u00ednica \u00a0del accionante \u00a0decidi\u00f3: \u00a0\u201cse \u00a0ordenar\u00e1 \u00a0a\u00a0 SaludCoop E.P.S. \u00a0que \u00a0programe una valoraci\u00f3n por un equipo multidisciplinario compuesto por los \u00a0especialistas \u00a0adscritos \u00a0a \u00a0su \u00a0red \u00a0de \u00a0servicios, \u00a0que indique el Dr. Hern\u00e1n \u00a0Yupanqui \u00a0(especialista \u00a0tratante) a efectos de que se establezca el tratamiento \u00a0a \u00a0seguir en el caso de la se\u00f1ora Glaris Mar\u00eda Roa S\u00e1nchez y en consecuencia, \u00a0se \u00a0le \u00a0practiquen \u00a0todos \u00a0los \u00a0procedimientos \u00a0e \u00a0intervenciones \u00a0que requiera, \u00a0incluyendo \u00a0la \u00a0cirug\u00eda \u00a0bari\u00e1trica, \u00a0si \u00a0ello \u00a0es \u00a0lo \u00a0que concluye el equipo \u00a0m\u00e9dico\u201d.\u00a0 \u00a0 Sentencia \u00a0T-264 \u00a0de \u00a02003 \u00a0M.P. \u00a0Humberto Sierra Porto. \u00a0\u00a0<\/p>\n<p>40 \u00a0Sobre \u00a0 el \u00a0consentimiento \u00a0informado \u00a0en \u00a0un \u00a0caso \u00a0de \u00a0Obesidad \u00a0M\u00f3rbida, \u00a0la \u00a0Corporaci\u00f3n \u00a0ha \u00a0se\u00f1alado \u00a0que\u00a0 \u00a0\u201ccuando \u00a0la \u00a0realizaci\u00f3n \u00a0 de \u00a0 un \u00a0 procedimiento \u00a0 m\u00e9dico, \u00a0implica \u00a0la \u00a0intervenci\u00f3n \u00a0o \u00a0manipulaci\u00f3n \u00a0del \u00a0cuerpo \u00a0del paciente, el m\u00e9dico tratante o los m\u00e9dicos que \u00a0hayan \u00a0intervenido \u00a0o \u00a0participado con sus conceptos cient\u00edficos especializados \u00a0en \u00a0la \u00a0elaboraci\u00f3n \u00a0de propuestas m\u00e9dicas que buscan solucionar los problemas \u00a0de \u00a0salud que aquejan al paciente, deber\u00e1n suministrar a \u00e9ste, la informaci\u00f3n \u00a0suficiente, \u00a0que \u00a0ajustada \u00a0a \u00a0la \u00a0realidad cient\u00edfica y f\u00e1ctica que rodean su \u00a0caso \u00a0en \u00a0particular en ese momento, permita que el paciente, haciendo uso de su \u00a0autonom\u00eda \u00a0individual, asienta sobre el procedimiento a \u00e9l propuesto, y acepte \u00a0en \u00a0consecuencia \u00a0someterse o no al mismo en aras de mejorar su estado de salud, \u00a0o \u00a0en \u00a0el \u00a0caso \u00a0extremo, \u00a0el \u00a0de \u00a0salvaguardar \u00a0su \u00a0propia vida\u201d Sentencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-1229 de 2005 M.P. Jaime Araujo Renter\u00eda. \u00a0\u00a0<\/p>\n<p>41 \u00a0Sentencia T-1229 de 2005. M.P. Jaime Ara\u00fajo Renter\u00eda. \u00a0\u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia T-163-09 \u00a0 (Marzo 16, Bogot\u00e1 DC.) \u00a0 Referencia: \u00a0Expediente T-2.074.102. \u00a0\u00a0 Accionante: \u00a0Roger \u00a0Rafael Rambao Guti\u00e9rrez. \u00a0\u00a0 Accionado: \u00a0Seguro \u00a0Social EPS y Nueva EPS \u00a0\u00a0 Fallo \u00a0 objeto \u00a0de \u00a0revisi\u00f3n: \u00a0sentencia \u00a0del \u00a0Juzgado Penal del Circuito de Soledad -Atl\u00e1ntico, \u00a0del \u00a0 \u00a0 \u00a0 7 \u00a0 \u00a0 \u00a0de \u00a0 \u00a0 \u00a0mayo \u00a0 \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"class_list":["post-16617","post","type-post","status-publish","format-standard","hentry","category-tutelas-2009"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/16617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=16617"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/16617\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=16617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=16617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=16617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}