{"id":18389,"date":"2024-06-12T16:22:56","date_gmt":"2024-06-12T16:22:56","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/06\/12\/c-445-11\/"},"modified":"2024-06-12T16:22:56","modified_gmt":"2024-06-12T16:22:56","slug":"c-445-11","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/c-445-11\/","title":{"rendered":"C-445-11"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia C-445\/11 \u00a0<\/p>\n<p>CARGO DE SUBINTENDENTE EN LA POLICIA NACIONAL-Requisito de no haber sido sancionado en los \u00faltimos tres a\u00f1os para ascender, no constituye una vulneraci\u00f3n del derecho a la igualdad\u00a0 \u00a0<\/p>\n<p>ASCENSO DE OFICIALES, NIVEL EJECUTIVO Y SUBOFICIALES DE LA POLICIA NACIONAL-Requisitos \u00a0<\/p>\n<p>ASCENSO DE PATRULLERO AL CARGO DE SUBINTENDENTE-Condiciones\u00a0 \u00a0<\/p>\n<p>CARRERA ADMINISTRATIVA-Modalidades\/CARRERA DE LA POLICIA NACIONAL-Es de origen constitucional\/POLICIA NACIONAL-Car\u00e1cter civil\/POLICIA NACIONAL-Concepto \u00a0<\/p>\n<p>El art\u00edculo 125 de la Constituci\u00f3n Pol\u00edtica prescribe la carrera como regla general en \u00e1mbito de la funci\u00f3n p\u00fablica y al tiempo contiene una enunciaci\u00f3n b\u00e1sica de los cargos que se except\u00faan de la misma, a saber: los de elecci\u00f3n popular, libre nombramiento y remoci\u00f3n, los de trabajadores oficiales y los dem\u00e1s que determine la ley. Hay, pues, una regla principal aplicable a la regulaci\u00f3n de la mayor\u00eda los empleos p\u00fablicos: la generalidad se sigue por la carrera administrativa como mandato cuya satisfacci\u00f3n se asegura mediante la reglamentaci\u00f3n del ingreso, ascenso y retiro de estos cargos a trav\u00e9s de un sistema normativo que propende por su edificaci\u00f3n objetiva y desprovista de visos de arbitrariedad. Esa categor\u00eda presenta dos modalidades principales: la carrera general y la especial, que al tiempo se subdivide de acuerdo con su origen, ora legal o constitucional. Las dos primeras, la carrera general y la especial de origen legal \u2013ordinario y extraordinario-, o sistemas espec\u00edficos de carrera administrativa, est\u00e1n bajo la administraci\u00f3n y vigilancia de la Comisi\u00f3n Nacional del Servicio Civil por disposici\u00f3n del art\u00edculo 130 de la Carta y de la Ley 909 de 2004, respectivamente. Como ejemplos de la carrera especial de origen constitucional tenemos: el de la Fuerza P\u00fablica, constituida por las Fuerzas Militares y la Polic\u00eda Nacional (art\u00edculos 217 y 218); el de la Fiscal\u00eda General de la Naci\u00f3n (art\u00edculo 253); el de la Rama Judicial del poder p\u00fablico (art\u00edculo 256, numeral 1\u00b0); el de la Contralor\u00eda General de la Rep\u00fablica (art\u00edculo 268 numeral 10\u00b0) y el de la Procuradur\u00eda General de la Naci\u00f3n (art\u00edculo 279). Es claro, por manifiesta disposici\u00f3n de la Carta, que la carrera de la Polic\u00eda Nacional es de las especiales, naturalmente, de origen constitucional. Ahora, aunque el art\u00edculo 218 superior atribuye al legislador la tarea de definir el r\u00e9gimen de carrera de la Polic\u00eda, ello siempre debe seguir el prop\u00f3sito constitucional de que la administraci\u00f3n p\u00fablica cuente con servidores altamente cualificados para asumir de manera profesional las importantes responsabilidades que la Constituci\u00f3n y las leyes han confiado a los organismo estatales, objetivo acentuado trat\u00e1ndose de actividades de la envergadura de las asignadas a la Polic\u00eda Nacional, garante de la armon\u00eda para el ejercicio arm\u00f3nico de las libertades y derechos reconocidas a los civiles. Con base en la concepci\u00f3n que de este organismo fij\u00f3 la Carta como \u201ccuerpo armado permanente de naturaleza civil, a cargo de la Naci\u00f3n, cuyo fin primordial es el mantenimiento de las condiciones necesarias para el ejercicio de los derechos y libertades p\u00fablicas, y para asegurar que los habitantes de Colombia convivan en paz\u201d. La jurisprudencia de este Alto Tribunal ha sostenido de manera reiterada y coincidente que \u00e9ste es un \u00f3rgano civil, con funciones esencialmente preventivas, orientado a precaver la alteraci\u00f3n del orden p\u00fablico, y en cuyas din\u00e1micas no rige la l\u00f3gica castrense. Resulta palmario que para la adecuada ejecuci\u00f3n de las funciones a cargo de la Polic\u00eda Nacional, el Constituyente previ\u00f3 un r\u00e9gimen especial de carrera cuya elaboraci\u00f3n estar\u00eda a cargo del legislador, por mandato del art\u00edculo 218 constitucional, en consideraci\u00f3n a la singular naturaleza de este cuerpo armado. Sobre el particular se ha sostenido que \u201cdada la trascendencia que para un Estado democr\u00e1tico representan las funciones que desempe\u00f1a la Polic\u00eda Nacional, el legislador ha buscado establecer un sistema de carrera que permita garantizar a sus miembros los derechos que de ella se derivan, como el ingreso en igualdad de oportunidades para quienes aspiran a ser parte de esas instituciones, el ascenso en la carrera por m\u00e9ritos, aptitudes y capacidades, y el retiro del servicio por las causales establecidas en la Constituci\u00f3n, como son: la calificaci\u00f3n insatisfactoria en el desempe\u00f1o del empleo, por violaci\u00f3n del r\u00e9gimen disciplinario, o por las dem\u00e1s causales previstas por la Carta Pol\u00edtica o por la ley.\u201d \u00a0<\/p>\n<p>REGIMEN ESPECIAL DE CARRERA DE LA POLICIA NACIONAL-Regulaci\u00f3n \u00a0<\/p>\n<p>POLICIA NACIONAL-Estructura\u00a0 \u00a0<\/p>\n<p>POLICIA NACIONAL-Par\u00e1metros generales para los ascensos \u00a0<\/p>\n<p>CARRERA PROFESIONAL DEL NIVEL EJECUTIVO DE LA POLICIA NACIONAL-R\u00e9gimen de ascenso\/NIVEL EJECUTIVO DE LA POLICIA NACIONAL-Homologaci\u00f3n\/INGRESO DEL PERSONAL DE SUBOFICIALES DE LA POLICIA A LA ESCALA JERARQUICA DEL NIVEL EJECUTIVO-Equivalencias\u00a0 \u00a0<\/p>\n<p>PERSONAL DEL NIVEL EJECUTIVO Y DE OFICIALES DE LA POLICIA NACIONAL-Factores generales que restringen las posibilidades de ascenso \u00a0<\/p>\n<p>EVALUACION DEL DESEMPE\u00d1O DEL PERSONAL DE LA POLICIA NACIONAL-R\u00e9gimen aplicable\/EVALUACION DEL DESEMPE\u00d1O DEL PERSONAL DE LA POLICIA NACIONAL-Etapas\u00a0 \u00a0<\/p>\n<p>REGIMEN DISCIPLINARIO PARA LA POLICIA NACIONAL-Modalidades\u00a0 \u00a0<\/p>\n<p>PRINCIPIO DE IGUALDAD-Subreglas\u00a0 \u00a0<\/p>\n<p>PRINCIPIO DE IGUALDAD-Car\u00e1cter relacional\u00a0 \u00a0<\/p>\n<p>JUICIO DE IGUALDAD-Supuestos o situaciones equiparables para establecer que es lo igual que merece un trato igual y que es lo divergente que exige un trato diferenciado\u00a0 \u00a0<\/p>\n<p>INGRESO Y ASCENSO DE OFICIALES, NIVEL EJECUTIVO Y SUBOFICIALES DE LA POLICIA NACIONAL-Pluralidad de reg\u00edmenes jur\u00eddicos que no pueden ser equiparados \u00a0<\/p>\n<p>INGRESO Y ASCENSO DE OFICIALES, NIVEL EJECUTIVO Y SUBOFICIALES DE LA POLICIA NACIONAL-Libre configuraci\u00f3n normativa reconocida al legislador\/POLICIA NACIONAL-Pluralidad de formas de ingreso y de ascenso\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Referencia: expediente D-8345 \u00a0<\/p>\n<p>Demanda de inconstitucionalidad contra el numeral 4\u00b0 del par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto Ley 1791 de 2000. \u00a0<\/p>\n<p>Actor:\u00a0 \u00a0<\/p>\n<p>Juli\u00e1n Arturo Polo Echeverri. \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>HUMBERTO ANTONIO SIERRA PORTO \u00a0<\/p>\n<p>Bogot\u00e1 D. C., veintis\u00e9is (26) de mayo de dos mil once (2011). \u00a0<\/p>\n<p>La Sala Plena de la Corte Constitucional, en cumplimiento de sus atribuciones constitucionales y de los requisitos y tr\u00e1mite establecidos en el decreto 2067 de 1991, ha proferido la siguiente \u00a0<\/p>\n<p>SENTENCIA \u00a0<\/p>\n<p>I. ANTECEDENTES: \u00a0<\/p>\n<p>En ejercicio de la acci\u00f3n p\u00fablica consagrada en el art\u00edculo 241 de la Constituci\u00f3n Pol\u00edtica, el ciudadano Juli\u00e1n Arturo Polo Echeverri M\u00e9ndez demand\u00f3 la constitucionalidad del numeral 4\u00b0 del par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto Ley 1791 de 2000, por la supuesta vulneraci\u00f3n del principio de igualdad.\u00a0 \u00a0<\/p>\n<p>La demanda ciudadana fue admitida mediante trav\u00e9s de auto del 25 de noviembre de 2010. En esta providencia se orden\u00f3 comunicar la iniciaci\u00f3n del presente proceso al Presidente del Congreso, al Presidente de la Rep\u00fablica y al Ministerio de Defensa Nacional para que, si lo consideraban oportuno, intervinieran directamente o por medio de apoderado, mediante escrito que deb\u00edan presentar dentro de los diez (10) d\u00edas siguientes al del recibo de la comunicaci\u00f3n respectiva, indicando las razones que, en su criterio, justifican la constitucionalidad o a inconstitucionalidad de la norma demandada. \u00a0<\/p>\n<p>De igual manera, se invit\u00f3 a la Academia Colombiana de Derecho Procesal y a las Facultades de Derecho de las Universidades Andes, Externado, Javeriana, Libre, Nacional, de Antioquia, Rosario y de Cartagena para que, si lo estimaban conveniente, intervinieran mediante escrito que deber\u00edan presentar dentro de los diez (10) d\u00edas siguientes al del recibo de la comunicaci\u00f3n respectiva, indicando las razones que, en su criterio, justifican la constitucionalidad o inconstitucionalidad de la norma demandada. \u00a0<\/p>\n<p>Por \u00faltimo, se orden\u00f3 correr el respectivo traslado al Procurador General de la Naci\u00f3n, para lo de su competencia. \u00a0<\/p>\n<p>Durante el t\u00e9rmino de fijaci\u00f3n en lista se recibieron las siguientes intervenciones del Ministerio de Defensa y el Instituto Colombiano de Derecho Procesal. El Concepto del Procurador fue radicado el d\u00eda 2 de febrero de 2011 en la Secretar\u00eda General de esta Corporaci\u00f3n. Cumplidos los tr\u00e1mites constitucionales y legales correspondientes, entra la Corte a decidir sobre la demanda de la referencia. \u00a0<\/p>\n<p>II. DISPOSICI\u00d3N DEMANDADA. \u00a0<\/p>\n<p>A continuaci\u00f3n se trascribe, subrayado, el enunciado normativo demandado: \u00a0<\/p>\n<p>DECRETO 1791 \u00a0<\/p>\n<p>(septiembre 14) \u00a0<\/p>\n<p>MINISTERIO DE DEFENSA NACIONAL \u00a0<\/p>\n<p>Por el cual se modifican las normas de carrera del Personal de Oficiales, Nivel Ejecutivo, Suboficiales y Agentes de la Polic\u00eda Nacional. \u00a0<\/p>\n<p>EL PRESIDENTE DE LA REP\u00daBLICA DE COLOMBIA, \u00a0<\/p>\n<p>en ejercicio de las facultades extraordinarias que le confiere la Ley 578 de 2000 \u00a0<\/p>\n<p>DECRETA: \u00a0<\/p>\n<p>ART\u00cdCULO 21. REQUISITOS PARA ASCENSO DE OFICIALES, NIVEL EJECUTIVO Y SUBOFICIALES. Los oficiales, nivel ejecutivo a partir del grado de subintendente y suboficiales de la Polic\u00eda Nacional, podr\u00e1n ascender en la jerarqu\u00eda al grado inmediatamente superior cuando cumplan los siguientes requisitos: \u00a0<\/p>\n<p>1. Tener el tiempo m\u00ednimo de servicio establecido para cada grado. \u00a0<\/p>\n<p>2. Ser llamado a curso. \u00a0<\/p>\n<p>3. Adelantar y aprobar los cursos de capacitaci\u00f3n establecidos por el Consejo Superior de Educaci\u00f3n Policial. \u00a0<\/p>\n<p>4. Tener aptitud psicof\u00edsica de acuerdo con lo contemplado en las normas sobre Incapacidades e Invalideces. \u00a0<\/p>\n<p>5. Obtener la clasificaci\u00f3n exigida para ascenso. \u00a0<\/p>\n<p>6. Para oficiales, concepto favorable de la Junta Asesora del Ministerio de Defensa para la Polic\u00eda Nacional; para nivel ejecutivo y suboficiales, concepto favorable de la Junta de Evaluaci\u00f3n y Clasificaci\u00f3n. \u00a0<\/p>\n<p>7. Hasta el grado de Coronel, acreditar un tiempo m\u00ednimo de dos (2) a\u00f1os en el respectivo grado, en labores operativas, de investigaci\u00f3n, docencia, desempe\u00f1o de funciones en la Gesti\u00f3n General del Ministerio de Defensa Nacional, de acuerdo con las disposiciones que para tal efecto presente a consideraci\u00f3n del Ministro de Defensa Nacional el Director General de la Polic\u00eda Nacional. \u00a0<\/p>\n<p>8. Para el personal que permanezca en el Cuerpo Administrativo, acreditar un curso de actualizaci\u00f3n profesional en su especialidad, con una duraci\u00f3n no inferior a ciento veinte (120) horas. \u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>PARAGRAFO 4. Podr\u00e1n concursar para ingresar como Subintendente los Patrulleros en servicio activo, previo el lleno de los siguientes requisitos: \u00a0<\/p>\n<p>1. Solicitud escrita a la Direcci\u00f3n General de la Polic\u00eda Nacional. \u00a0<\/p>\n<p>2. Tener la aptitud sicof\u00edsica de acuerdo con las normas vigentes. \u00a0<\/p>\n<p>3. Tener un tiempo m\u00ednimo de cinco (5) a\u00f1os de servicio en la Instituci\u00f3n como Patrullero. \u00a0<\/p>\n<p>4. No haber sido sancionado en los \u00faltimos tres (3) a\u00f1os. \u00a0<\/p>\n<p>5. Concepto favorable de la Junta de Clasificaci\u00f3n y Evaluaci\u00f3n respectiva. \u00a0<\/p>\n<p>El personal seleccionado deber\u00e1 adelantar y aprobar un curso de capacitaci\u00f3n cuya duraci\u00f3n no ser\u00e1 inferior a seis (6) meses. \u00a0<\/p>\n<p>Se except\u00faa de lo dispuesto en este par\u00e1grafo al personal de patrulleros que a la entrada en vigencia del presente Decreto cumpla antig\u00fcedad para ascenso hasta en el mes de septiembre del a\u00f1o 2001, sin perjuicio del cumplimiento de los dem\u00e1s requisitos que para el efecto exige la Ley.\u201d \u00a0<\/p>\n<p>III. ARGUMENTOS DE LA DEMANDA. \u00a0<\/p>\n<p>A juicio del actor, el enunciado normativo contenido en el numeral 4\u00b0 del par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto en cuesti\u00f3n desconoce el art\u00edculo 13 de la Constituci\u00f3n Nacional. \u00a0<\/p>\n<p>El cargo expuesto gira alrededor de una supuesta contradicci\u00f3n entre el aparte acusado y el contenido del derecho a la igualdad pues, seg\u00fan el actor, la norma plantea una trato discriminatorio injustificado entre los patrulleros y los dem\u00e1s miembros del cuerpo de Polic\u00eda Nacional \u00a0pues los primeros, a diferencia de los segundos, para ascender dentro de la estructura policial tienen que acreditar \u201cno haber sido sancionado[s] en los \u00faltimos tres (3) a\u00f1os.\u201d \u00a0<\/p>\n<p>El cargo propuesto por el ciudadano se condensa en la siguiente formulaci\u00f3n: \u201csi se observa con detenimiento la norma, se puede inferir razonablemente que no existe justificaci\u00f3n alguna para legitimar el trato desigual a quienes se encuentran en el grado de patrullero, frente a los del grado Comisario, Subcomisario, Intendente Jefe, Intendente, Subintendente que hacen parte del Nivel Ejecutivo, pues no es proporcional, razonable ni coherente, que se exija un desempe\u00f1o funcional intachable a quien pretende ascender a un rango inferior, y no sea requisito la carencia de antecedentes a quienes pretender [sic] ascender a cargos de mayor confianza, responsabilidad, y mucho mayor desempe\u00f1o; situaci\u00f3n que refleja la desproporci\u00f3n incoherencia y trato desigual que le imprime el precepto normativo demandado a los funcionarios de la polic\u00eda que ostentan el grado de PATRULLEROS frente a los policiales DEL MISMO NIVEL EJECUTIVO para quienes no interesa si fueron sancionados en los \u00faltimos tres (3) a\u00f1os situaci\u00f3n que pone de relieve y de manera objetiva la discriminaci\u00f3n injustificada.\u201d1 \u00a0<\/p>\n<p>De forma subsiguiente aleg\u00f3 el actor, \u201cde igual manera el propio art\u00edculo 21 ibidem, regula el tema del ascenso para oficiales, y suboficiales, sin embargo a ninguno de ellos se les impuso la exigencia de no haber sido sancionado [sic] en los \u00faltimos tres (3) a\u00f1os, situaci\u00f3n que rompe el trato igual para el personal de la Polic\u00eda Nacional.\u201d2 Todo lo anterior para justificar el cargo por violaci\u00f3n del principio de igualdad, dado un trato que, a juicio del demandante, resultaba injustificadamente discriminatorio en virtud de la existencia de una carga exclusivamente impuesta al personal de polic\u00eda con un menor rango dentro de la estructura jer\u00e1rquica.\u00a0 \u00a0<\/p>\n<p>IV. INTERVENCIONES. \u00a0<\/p>\n<p>El ciudadano N\u00e9stor Ra\u00fal S\u00e1nchez Baptista, actuando en representaci\u00f3n del Instituto Colombiano del Derecho Procesal, defendi\u00f3 la inconstitucionalidad de la expresi\u00f3n \u201cno haber sido sancionado en los \u00faltimos tres (3) a\u00f1os\u201d contenida en el par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto-Ley 1791 de 2000. \u00a0<\/p>\n<p>Para apoyar su dicho inicialmente se hizo una breve caracterizaci\u00f3n del n\u00facleo esencial del derecho a la igualdad con base en la reiterada jurisprudencia constitucional de conformidad con la cual el principio de igualdad se descompone en dos que permiten su aplicaci\u00f3n en casos concretos en los eventos en los cuales la ley establece tratos desiguales, en los que se debe establecer: \u00a0<\/p>\n<p>&#8220;a. Si no hay ninguna raz\u00f3n suficiente para la permisi\u00f3n de un tratamiento desigual, entonces est\u00e1 ordenado un tratamiento igual. \u00a0<\/p>\n<p>b. Si hay una raz\u00f3n suficiente para ordenar un tratamiento desigual, entonces est\u00e1 ordenado un tratamiento desigual.\u201d3 \u00a0<\/p>\n<p>Seguidamente se explic\u00f3, a manera de ilustraci\u00f3n, que de acuerdo con la jurisprudencia constitucional la resoluci\u00f3n de conflictos o tensiones en que tenga incidencia el derecho a la igualdad se debe efectuar el denominado \u201ctest de igualdad y de razonabilidad [a fin de] reconocer o excluir los tratos discriminatorios frente a una situaci\u00f3n dada. As\u00ed, [la Corte] estima necesario hacerlo [el test] respecto de la primera cuando: a) Est\u00e1 de por medio una clasificaci\u00f3n sospechosa; b) Cuando la medida recae en personas con debilidad manifiesta, grupos marginados o discriminados; c) Cuando la medida que hace una distinci\u00f3n entre personas o grupos afecta gravemente el goce de un derecho fundamental y d) Cuando la medida crea un privilegio. Y en cuanto al test de razonabilidad, debe examinarse si el fin de la medida [es] leg\u00edtimo e importante, pero adem\u00e1s imperioso. El medio escogido debe ser no s\u00f3lo adecuado y efectivamente conducente, sino adem\u00e1s necesario, o sea, que no pueda ser remplazado por un medio alternativo menos lesivo. Este exige que los beneficios de adoptar la medida excedan claramente las restricciones impuestas sobre otros principios y valores constitucionales por la medida.\u201d4 \u00a0<\/p>\n<p>Con base en lo antedicho arguy\u00f3 el interviniente, en relaci\u00f3n con la disposici\u00f3n cuestionada, que \u201cexiste un evidente tratamiento desigual por parte de la ley al establecerse en el par\u00e1grafo 40 demandado un requisito espec\u00edfico adicional para ascender al grado de Subintendente de la Instituci\u00f3n por parte de los Patrulleros, sin que, por otra parte, se encuentre raz\u00f3n suficiente para que tal requisito de la ausencia de sanciones dentro de los anteriores tres (3) a\u00f1os no sea exigible a los Comisarios, Subcomisarlos, Intendentes Jefe, Intendentes y Subintendentes. \u00a0<\/p>\n<p>Por lo que, efectivamente, encontramos un trato discriminatorio que hace m\u00e1s gravosas las exigencias para acceder al ascenso a una categor\u00eda de servidores de la Polic\u00eda Nacional -la de m\u00e1s bajo rango- como es la de los Patrulleros, sin que exista o sea identificable la raz\u00f3n suficiente de dicha discriminaci\u00f3n que se torna, en consecuencia, en ileg\u00edtima, desproporcionada, injustificada y, con ello, en Inconstitucional. En este caso se hace evidente que &#8220;si no hay ninguna raz\u00f3n suficiente para la permisi\u00f3n de un tratamiento desigual, entonces est\u00e1 ordenado un tratamiento igual, y que si no hay una raz\u00f3n suficiente para ordenar un tratamiento desigual, entonces no est\u00e1 ordenado un tratamiento desigual. Y se configura la violaci\u00f3n del derecho a la igualdad en la medida en que la ley da un trato desigual a situaciones de hecho que no ameritan, ni legal ni constitucionalmente, un tratamiento diverso, que establezca unos requisitos distintos y adicionales a una categor\u00eda de servidores para obtener el ascenso a que tienen derecho legalmente, en relaci\u00f3n con los restantes a que se refiere el decreto 1. 791 de 2.000\u201d5 \u00a0<\/p>\n<p>Adicionalmente se adujo que, pese a no haberse demandado, el par\u00e1grafo de la referencia va en contrav\u00eda de lo previsto, como regla general, para todo el sector p\u00fablico en el art\u00edculo 38 de la ley 734 de 2002, \u201cpor la cual se expide el C\u00f3digo Disciplinario \u00danico\u201d, seg\u00fan el cual \u201ctambi\u00e9n constituyen inhabilidades para desempe\u00f1ar cargos p\u00fablicos, a partir de la ejecutoria del fallo, las siguientes:\u00a0 \u00a0<\/p>\n<p>(\u2026) \u00a0<\/p>\n<p>2. Haber sido sancionado disciplinariamente tres o m\u00e1s veces en los \u00faltimos cinco (5) a\u00f1os por faltas graves o leves dolosas o por ambas. Esta inhabilidad tendr\u00e1 una duraci\u00f3n de tres a\u00f1os contados a partir de la ejecutoria de la \u00faltima sanci\u00f3n.\u201d6 \u00a0<\/p>\n<p>Lo anterior en virtud de que, desde este punto de vista, \u201ctampoco se encuentra debidamente justificada la regulaci\u00f3n distinta y exclusiva para el caso de los patrulleros aspirantes a subintendentes, establecida en forma m\u00e1s estricta que para el resto de los servidores p\u00fablicos en lo relativo a los antecedentes disciplinarios.\u201d7 \u00a0<\/p>\n<p>En consecuencia se solicit\u00f3 declarar la inexequibilidad por inconstitucional de la expresi\u00f3n \u201cno haber sido sancionado en los \u00faltimos tres (3) a\u00f1os\u201d contenida en el par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto-Ley 1791 de 2000.\u00a0 \u00a0<\/p>\n<p>ii) Ministerio de Defensa Nacional. \u00a0<\/p>\n<p>Sandra Marcela Parada Aceros present\u00f3 intervenci\u00f3n oportuna en calidad de apoderada especial del Ministerio de Defensa a efectos de defender la constitucionalidad de la formulaci\u00f3n demandada. \u00a0<\/p>\n<p>Para fundamentar su intervenci\u00f3n se hizo igualmente una descripci\u00f3n introductoria de la igualdad como criterio relacional cuya valoraci\u00f3n siempre implica el establecimiento de la relaci\u00f3n entre, al menos, dos personas, objetos o situaciones. Anot\u00f3 que, sin embargo, el art\u00edculo 13 de la Constituci\u00f3n no prescribe siempre un trato igual a todos los sujetos del derecho, o destinatarios de las normas, puesto que de acuerdo con el ordenamiento constitucional, algunos criterios de diferenciaci\u00f3n \u201cest\u00e1n expresamente proscritos por la Constituci\u00f3n y otros son especialmente invocados para promover la igualdad sustancial y con ello el ideal de justicia contenido en el pre\u00e1mbulo.\u201d8 \u00a0<\/p>\n<p>Para juzgar la constitucionalidad de un trato discriminatorio se debe acudir al juicio de proporcionalidad que obliga a que \u201clos medios escogidos por el legislador no s\u00f3lo deb[an] guardar proporcionalidad con los fines buscados por la norma, sino compart\u00edr [sic] su car\u00e1cter de legitimidad.\u201d As\u00ed, en palabras de la interviniente, \u201cel principio de proporcionalidad busca que la medida no s\u00f3lo tenga fundamento legal, sino que sea aplicada de tal manera que los intereses jur\u00eddicos de otras personas o grupos no se vean afectados, o que ello sucede en grado m\u00ednimo. De esta forma, la comunidad queda resguardada de los excesos o abusos de poder que podr\u00edan provenir del empleo indiscriminado de la facultad legislativa o de la discrecionalidad atribuida a la administraci\u00f3n.\u201d9 En \u00faltimas, se se\u00f1ala en el escrito, el juicio de igualdad requiere la realizaci\u00f3n de una valoraci\u00f3n que permita identificar \u201csi el dispositivo normativo acusado i) persigue un objetivo con el trato diferente, ii) si ese objetivo es v\u00e1lido y, finalmente, iii) si el trato diferencial es razonable.\u201d10 \u00a0<\/p>\n<p>Posteriormente la interviniente subray\u00f3 las reglas jurisprudenciales establecidas en m\u00faltiples sentencias de esta Corporaci\u00f3n en relaci\u00f3n con este t\u00f3pico, en las que se ha determinado la inexistencia de un trato discriminatorio frente a la instauraci\u00f3n de un r\u00e9gimen especial de seguridad social a favor de los miembros de la fuerza p\u00fablica.\u00a0 \u00a0<\/p>\n<p>De manera consecuente sostuvo que \u201cel decreto 2070 de 2003 se limit\u00f3 entonces fue a reformar el r\u00e9gimen existente de conformidad con las facultades otorgadas en la Ley 797 de 2003, mediante la cual el Congreso confiri\u00f3 por seis meses, al Presidente de la Rep\u00fablica precisas facultades extraordinarias, para expedir normas con fuerza de ley que reformaran el r\u00e9gimen pensional propio de las fuerzas militares dentro del marco de especialidad previsto en el art\u00edculo 217 de la Constituci\u00f3n Pol\u00edtica.\u201d11De hecho, a este respecto fue resaltado lo dicho en sentencia C-101 de 2003 en cuanto a que \u201cno es procedente un examen de aspectos aislados de una prestaci\u00f3n entre dos reg\u00edmenes prestacionales diferentes, ya que la desventaja que se pueda constatar en un tema, puede aparecer compensada por una prerrogativa en otras materias del mismo r\u00e9gimen.\u201d12 \u00a0<\/p>\n<p>M\u00e1s adelante la interviniente hizo alusi\u00f3n a la ineptitud sustantiva de la demanda por ausencia de requisitos m\u00ednimos para un pronunciamiento de fondo, frente a lo que se concluy\u00f3 que \u201caplicada la argumentaci\u00f3n anterior al caso concreto objeto de estudio es pertinente advertir que en su escrito inicial como en el de la correcci\u00f3n a la m\u00edsma [sic] el accionante vuelve una y otra vez a su inconformidad con el criterio sentado de [sic] la Corte en su sentencia C 1299 de 2005, solicitando no su constitucionalidad condicionada de las disposiciones acusadas [sic] sino la inconstitucionalidad de las m\u00edsmas [sic], hecho que fundamenta el sentido de la acci\u00f3n p\u00fablica de inexequibilidad lo permito [sic].\u201d13 \u00a0<\/p>\n<p>As\u00ed mismo, ratific\u00f3 las diferencias que jurisprudencialmente se han desarrollado en pro de la distinci\u00f3n del r\u00e9gimen de las Fuerzas Militares y el de la Polic\u00eda Nacional, para concluir que \u201ccon la disposici\u00f3n acusada el legislador, partiendo de las formulaciones constitucionales, tom\u00f3 en cuenta el car\u00e1cter civil del personal de polic\u00eda y que la finalidad que persigue al incluir el arresto por delitos dolosos como causal de separaci\u00f3n de la carrera en la Polic\u00eda Nacional y no hacer lo mismo en las Fuerzas Militares, radica en la necesidad de exigir una mayor pulcritud en el comportamiento de los miembros de la polic\u00eda dada su misi\u00f3n relacionada con el mantenimiento, entre la sociedad civil, de las condiciones necesarias para el ejercicio de los derechos fundamentales y la convivencia pac\u00edfica. (C.P art. 218). Al respecto debe tomarse en cuenta que la labor de la Polic\u00eda es esencialmente preventiva e implica un contacto m\u00e1s directo con la ciudadan\u00eda, lo que obliga a extremar las medidas tendientes a proteger a la poblaci\u00f3n civil.\u201d14 \u00a0<\/p>\n<p>Para culminar la representante del Ministerio de Defensa adujo que no es viable efectuar un juicio de igualdad entre las normas que regulan el ascenso de \u00a0los patrulleros y el resto del personal perteneciente al nivel ejecutivo y de suboficiales, simplemente porque se trata de cargos jer\u00e1rquicamente distintos. Para sustentar su postura la representante del Ministerio de Defensa afirm\u00f3 que \u201cno existe ninguna discriminaci\u00f3n injustificada o justificada, siendo pertinente aclarar, que no cabe plantear una relaci\u00f3n de igualdad y por ende una vulneraci\u00f3n a la m\u00edsma [sic], si se toman como t\u00e9rminos de comparaci\u00f3n en primer lugar, las personas que no han podido ingresa al grado de Subteniente y de ah\u00ed en adelante a los dem\u00e1s grados, en raz\u00f3na [sic] que los patrulleros forman parte del personal de base de la instituci\u00f3n, lo cu\u00e1l incluso como lo plantea la ley 1405 de 2010, no lo contempla dentro \u00a0de los tiempos m\u00ednimos, para ascender (\u2026)Y en segundo orden [sic], las personas que ya obtuvieron su ascenso a Subteniente, intendente, intendente [sic] o Jefe y Subcomisario. Se tarta de situaciones diferentes y por consiguiente, su tratamiento legal puede no ser an\u00e1logo.\u201d15 \u00a0<\/p>\n<p>Corolario, el Ministerio de Defensa aleg\u00f3 la inexistencia de motivo alguno para negar la constitucionalidad de la norma demandada con base en una aparente violaci\u00f3n del principio de igualdad.\u00a0 \u00a0<\/p>\n<p>V. CONCEPTO DEL PROCURADOR\u00a0 \u00a0<\/p>\n<p>Mediante concepto 5081 de 2011, el Procurador General de Naci\u00f3n solicit\u00f3 la declaratoria de inconstitucionalidad del numeral 4\u00b0 del par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto-Ley 1791 de 2000. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>De acuerdo con esa entidad, el problema jur\u00eddico consiste en establecer si el numeral en cuesti\u00f3n, al imponer a los patrulleros un requisito habilitante para el ascenso al grado de subintendente de la Polic\u00eda Nacional, refleja una discriminaci\u00f3n injustificada que vulnera as\u00ed el principio de igualdad puesto que el ascenso a los dem\u00e1s cargos del mismo organismo no est\u00e1 supeditado al referido requerimiento: no haber sido sancionado en los \u00faltimos tres (3) a\u00f1os. \u00a0<\/p>\n<p>Para abordar el estudio de constitucionalidad de la norma se hizo, primero, una referencia sucinta a la naturaleza de la carrera policial como un r\u00e9gimen especial para la regulaci\u00f3n del ingreso, ascensos, retiro y permanencia al servicio de esta organizaci\u00f3n que, de conformidad con el art\u00edculo 218 superior, est\u00e1 instituida como \u201ccuerpo armado permanente de naturaleza civil, a cargo de la Naci\u00f3n, cuyo fin primordial es el mantenimiento de las condiciones necesarias para el ejercicio de los derechos y libertades p\u00fablicas, y para asegurar que los habitantes de Colombia convivan en paz [y respecto del cual] la ley determinar\u00e1 su r\u00e9gimen de carrera, prestacional y disciplinario.\u201d16 \u00a0<\/p>\n<p>Acto seguido la Procuradur\u00eda subray\u00f3 que, al tenor del art\u00edculo 216 superior y reiterada jurisprudencia constitucional17, la Polic\u00eda Nacional hace parte de la Fuerza P\u00fablica, en raz\u00f3n de lo cual las principales funciones a ella asignada son la generaci\u00f3n de condiciones que permitan a los asociados ejercer a plenitud sus derechos y libertades dentro del marco de la Constituci\u00f3n y la ley adem\u00e1s del aseguramiento de la convivencia pac\u00edfica dentro del seno de la sociedad colombiana.\u00a0 \u00a0<\/p>\n<p>Afirm\u00f3 que la carrera de la Polic\u00eda Nacional, en tanto r\u00e9gimen especial de origen constitucional, \u201cdebe cumplir una serie de condiciones aplicables a todos los reg\u00edmenes de carrera, a saber: i) respetar los principios constitucionales relativos a la funci\u00f3n p\u00fablica; ii) acatar de los principios constitucionales de la carrera, en especial los de igualdad y de m\u00e9rito; iii) acoger el principio de raz\u00f3n suficiente para su implementaci\u00f3n; iv) y analizar, de manera previa, las especificidades de la funci\u00f3n a cumplir por la entidad y por sus servidores, para su implementaci\u00f3n.\u201d18 \u00a0<\/p>\n<p>La Vista Fiscal se\u00f1al\u00f3 igualmente que, no obstante el amplio margen de configuraci\u00f3n legislativa de que goza el legislador para la regulaci\u00f3n de los reg\u00edmenes especiales, como el de carrera de la Polic\u00eda Nacional, los principios constitucionales de igualdad y de m\u00e9rito representan l\u00edmites incuestionables al ejercicio legislativo, lo que claramente se ve manifestado en la edificaci\u00f3n de procesos objetivos de selecci\u00f3n, de ascenso y de permanencia en el servicio. \u00a0<\/p>\n<p>Concretamente en relaci\u00f3n con el principio de igualdad, sostuvo que su aplicaci\u00f3n no es predicable exclusivamente de los aspirantes a un cargo, sino que se extiende tambi\u00e9n al r\u00e9gimen o sistema de carrera en su integridad. En sustento de esta afirmaci\u00f3n se hizo menci\u00f3n a la sentencia C-901 de 2008, en cuanto a que: \u201cel numeral 7 del art\u00edculo 40 de la Constituci\u00f3n Pol\u00edtica establece el derecho fundamental de todo ciudadano a participar en condiciones de igualdad en la conformaci\u00f3n, ejercicio y control del poder pol\u00edtico. Para hacer efectivo este derecho puede, entre otras, tener acceso al desempe\u00f1o de funciones y cargo p\u00fablicos, acogi\u00e9ndose a las reglas del concurso p\u00fablico y con sujeci\u00f3n a los m\u00e9ritos y calidades propios (C.P. art 125). Esta posibilidad se deriva de la Declaraci\u00f3n Universal de los Derechos Humanos que, reconociendo la igualdad de todos los ciudadanos ante la ley, declara que pueden acceder (a todas las dignidades, todos los puestos o empleos, seg\u00fan su capacidad y sin otra distinci\u00f3n que aquella de sus virtudes y talentos [sic]\u201d.19 \u00a0<\/p>\n<p>Acto seguido la Procuradur\u00eda concluy\u00f3 que \u201cde ah\u00ed que haya precisado la Corte que el principio de igualdad est\u00e1 en contradicci\u00f3n con cualquier regulaci\u00f3n que establezca requisitos ajenos al m\u00e9rito y capacidad de los participantes, sin suficiente fundamento objetivo o que las pruebas no sean valoradas en forma razonable y proporcional a su importancia, teniendo en cuenta el cargo a proveer, pues con ello se estar\u00eda obstruyendo el derecho a acceder a los cargos p\u00fablicos en condiciones de igualdad\u201d20. \u00a0<\/p>\n<p>Adicionalmente, \u201cpor tratarse de la realizaci\u00f3n efectiva de principios y derechos constitucionales, no le est\u00e1 permitido al Legislador, en consecuencia, dise\u00f1ar sistemas espec\u00edficos de carrera y reglas particulares de concurso que obstruyan la participaci\u00f3n igualitaria de los ciudadanos o desconozcan los criterios del m\u00e9rito. Con independencia del origen constitucional o legal de un r\u00e9gimen de carrera la Corte ha puntualizado: \u00a0<\/p>\n<p>\u201c(&#8230;)Los presupuestos normativos de los sistemas de concursos de la carrera administrativa estar\u00e1n acordes con la Constituci\u00f3n: (i) si no se establece una distinci\u00f3n que disponga una regulaci\u00f3n para el ascenso en la carrera y otra m\u00e1s restrictiva para el ingreso a la misma; (ii) si no se derivan de las normas que regulan la carrera, condiciones de desigualdad que impidan la determinaci\u00f3n objetiva del m\u00e9rito de cada concursante; (iii) si no se incluyen \u00edtems de evaluaci\u00f3n cuya aplicaci\u00f3n proceda s\u00f3lo para algunos concursantes y no para todos; (iv) si no se disponen criterios de selecci\u00f3n que eval\u00faen la idoneidad frente a ciertas actividades espec\u00edficas o t\u00e9cnicas, en condiciones desiguales entre los aspirantes vinculados a la entidad y los no vinculados; (&#8230;) Una regulaci\u00f3n normativa que genere una situaci\u00f3n contraria a cualquiera de los supuestos anteriores es sin duda inconstitucional.\u201d21 \u00a0<\/p>\n<p>Con fundamento en las anteriores consideraciones la Procuradur\u00eda General de la Naci\u00f3n coligi\u00f3 que la formulaci\u00f3n normativa acusada presenta dos reparos desde el punto de vista de su constitucionalidad, a saber:\u00a0 \u00a0<\/p>\n<p>i) La vulneraci\u00f3n del derecho a la igualdad, \u201cpues para el ascenso de los oficiales de la polic\u00eda nacional no se exige la ausencia de sanciones en los \u00faltimos tres a\u00f1os, como tampoco se lo exige para los suboficiales, salvo para los patrulleros en servicio activo, quienes son los \u00fanicos que para ascender a subintendentes deben cumplir esa exigencia [es decir que] si un servidor de la polic\u00eda recibe una sanci\u00f3n en los \u00faltimos tres a\u00f1os, \u00e9sta s\u00f3lo impide el ascenso de los patrulleros, pero no es un obst\u00e1culo para el ascenso de los dem\u00e1s suboficiales y para los oficiales.\u201d22 Circunstancia que a su juicio representa una discriminaci\u00f3n negativa e injustificada en vista de que el anterior deber\u00eda ser un criterio excluyente para el ascenso a todos los cargos que integren la carrera policial, no s\u00f3lo al de patrulleros. Se aleg\u00f3, entonces, que \u201cno es razonable ni objetivo exigir buena conducta s\u00f3lo a los patrulleros, uno de los grados menores en la jerarqu\u00eda de la polic\u00eda, y no exigirla tambi\u00e9n a los grados dentro de dicha jerarqu\u00eda.\u201d23 \u00a0<\/p>\n<p>ii) La inhabilidad planteada en la norma no distingue entre la clase de falta cometida y la clase de sanci\u00f3n impuesta. A este respecto sostuvo que \u201cpara efectos del ascenso es igual que un patrullero sea sancionado por una falta grav\u00edsima a que lo sea por una falta grave o leve.\u201d24 Esta generalidad, de acuerdo con la Vista Fiscal, desconoce el principio de proporcionalidad en la medida en que son equiparadas situaciones dis\u00edmiles, y que, por ende, no merecen el mismo tratamiento.\u00a0 \u00a0<\/p>\n<p>Asimismo, en cuanto a los t\u00edtulos de imputaci\u00f3n, la Procuradur\u00eda adujo que no es admisible la equiparaci\u00f3n de una falta dolosa y una culposa puesto que la misma Carta, al establecer en su art\u00edculo 122 las inhabilidades, tiene en cuenta tanto la clase de sanci\u00f3n como el t\u00edtulo de imputaci\u00f3n jur\u00eddica, circunstancia que desde\u00f1a la norma demandada. Se tuvo que la expresi\u00f3n \u201csancionado\u201d, sin mayores precisiones, resulta vaga e indeterminada, dado que no demuestra un contenido axiol\u00f3gicamente neutro, lo que impide su adecuada interpretaci\u00f3n de conformidad con lo dicho por la Corte Constitucional. 25 \u00a0<\/p>\n<p>En raz\u00f3n de los argumentos expuesto, el Ministerio P\u00fablico solicit\u00f3 la declaratoria de \u00a0inexequibilidad del numeral 4\u00b0 del par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto ley 1791 de 2000. \u00a0<\/p>\n<p>VI. CONSIDERACIONES Y FUNDAMENTOS. \u00a0<\/p>\n<p>1. Competencia \u00a0<\/p>\n<p>La Corte es competente para conocer del proceso de la referencia, de conformidad con el art\u00edculo 241 numeral 1\u00b0 de la Constituci\u00f3n Pol\u00edtica. \u00a0<\/p>\n<p>2. El asunto objeto de examen.\u00a0 \u00a0<\/p>\n<p>El actor formula un cargo de inconstitucionalidad contra el numeral 4 del par\u00e1grafo 4 del art\u00edculo 21 del Decreto 1791 de 2000. Este precepto se\u00f1ala que para poder concursar para ingresar como Subintendente los Patrulleros en servicio activo, se debe reunir, entre otros, el siguiente requisito: \u00a0<\/p>\n<p>De acuerdo con este inciso, la promoci\u00f3n de un patrullero al cargo de subintendente presupone la realizaci\u00f3n de un concurso para cuyo ingreso es necesario acreditar, entre otros, el requisito de no haber sido sancionado en los \u00faltimos tres (3) a\u00f1os. En principio, este precepto no especifica la naturaleza de la sanci\u00f3n, pero como se expondr\u00e1 m\u00e1s adelante ha de entenderse que es de car\u00e1cter disciplinario debido a que una condena por sentencia ejecutoriada a la pena principal de prisi\u00f3n\u00a0o de arresto por delitos dolosos, constituye causal para la disponer la separaci\u00f3n absoluta del servicio, de acuerdo con el art\u00edculo 66 de este mismo Decreto. \u00a0<\/p>\n<p>Entonces, para que un patrullero pueda acceder al cargo de subintendente es menester, en primera medida, que supere un concurso para cuya participaci\u00f3n est\u00e1 condicionado, entre otros, al cumplimiento del requisito de no haber sido sancionado en los \u00faltimos tres (3) a\u00f1os a una sanci\u00f3n que conlleve a la pena principal de prisi\u00f3n o arresto por delitos dolosos. A lo que le sigue adelantar y aprobar un curso de capacitaci\u00f3n de una duraci\u00f3n no menor a seis (6) meses y por \u00faltimo, el concepto favorable de la Junta de Calificaci\u00f3n y Evaluaci\u00f3n respectiva. \u00a0<\/p>\n<p>El texto normativo demandado, el numeral 4\u00ba del par\u00e1grafo 4\u00ba del art\u00edculo 21 del Decreto-Ley 1791 de 2000, est\u00e1 ubicado en el cap\u00edtulo III del t\u00edtulo III relativo a la administraci\u00f3n del personal de la Polic\u00eda Nacional. En el cap\u00edtulo III se regula el ascenso del personal, que est\u00e1 condicionado en general al cumplimiento de \u201clos requisitos establecidos, dentro del orden jer\u00e1rquico, de acuerdo con las vacantes existentes, conforme al Decreto de planta y con sujeci\u00f3n a las precedencias de la clasificaci\u00f3n que establece el Decreto de Evaluaci\u00f3n del Desempe\u00f1o.\u201d26 \u00a0<\/p>\n<p>La norma cuestionada, el art\u00edculo 21, se\u00f1ala en particular los requisitos para ascenso de oficiales, nivel ejecutivo y suboficiales. En el primer inciso se dispone que los oficiales, nivel ejecutivo a partir del grado de subintendente y suboficiales de la Polic\u00eda Nacional \u201cpodr\u00e1n ascender en la jerarqu\u00eda al grado inmediatamente superior cuando cumplan los siguientes requisitos. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Tener el tiempo m\u00ednimo de servicio establecido para cada grado. \u00a0\u00a0<\/p>\n<p>2. Ser llamado a curso.\u00a0 \u00a0\u00a0<\/p>\n<p>3. Adelantar y aprobar los cursos de capacitaci\u00f3n establecidos por el Consejo Superior de Educaci\u00f3n Policial. \u00a0\u00a0<\/p>\n<p>4. Tener aptitud psicof\u00edsica de acuerdo con lo contemplado en las normas sobre Incapacidades e Invalideces y\u00a0 \u00a0\u00a0<\/p>\n<p>5. Obtener la clasificaci\u00f3n exigida para ascenso (\u2026)\u201d \u00a0 \u00a0<\/p>\n<p>Se tiene entonces que para el ascenso del personal perteneciente a estos cargos es necesario acreditar determinados requisitos generales27, a saber: i) cumplir con el tiempo m\u00ednimo de servicio exigido para cada grado, as\u00ed como ii) la aptitud psicof\u00edsica de acuerdo con las respectivas normas sobre incapacidades e 28invalideces; iii) ser llamado a curso; iv) adelantar y aprobar los cursos de capacitaci\u00f3n fijados por el Consejo Superior de Educaci\u00f3n Policial y finalmente v) obtener la clasificaci\u00f3n exigida para ascenso de acuerdo con el Decreto 1800 de 2000. Adem\u00e1s, la norma hace una distinci\u00f3n en el sentido de que, trat\u00e1ndose de oficiales, se requiere concepto favorable de la Junta Asesora del Ministerio de Defensa para la Polic\u00eda Nacional; mientras que para nivel ejecutivo y suboficiales, se exige concepto favorable de la Junta de Evaluaci\u00f3n y Clasificaci\u00f3n.29 \u00a0<\/p>\n<p>A juicio del actor de la comparaci\u00f3n entre los dos reg\u00edmenes jur\u00eddicos surge una vulneraci\u00f3n del principio y el derecho a la igualdad. Expl\u00edcitamente el actor alega que existe una contradicci\u00f3n entre el aparte acusado y el contenido del derecho a la igualdad, debido a que dicha norma plantea una trato discriminatorio injustificado entre los patrulleros y los dem\u00e1s miembros del cuerpo de polic\u00eda pues los primeros, a diferencia de los segundos, para ascender dentro de la estructura policial tienen que acreditar \u201cno haber sido sancionado[s] en los \u00faltimos tres (3) a\u00f1os\u201d, por mandato numeral 4\u00b0 del par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto-Ley 1791 de 2000, norma que se demanda.\u00a0 \u00a0<\/p>\n<p>Textualmente puntualiz\u00f3 el actor en demanda de inconstitucionalidad: \u201csi se observa con detenimiento la norma, se puede inferir razonablemente que no existe justificaci\u00f3n alguna para legitimar el trato desigual a quienes se encuentran en el grado de patrullero, frente a los del grado Comisario, Subcomisario, Intendente Jefe, Intendente, Subintendente que hacen parte del Nivel Ejecutivo, pues no es proporcional, razonable ni coherente, que se exija un desempe\u00f1o funcional intachable a quien pretende ascender a un rango inferior, y no sea requisito la carencia de antecedentes a quienes pretender [sic] ascender a cargos de mayor confianza, responsabilidad, y mucho mayor desempe\u00f1o; situaci\u00f3n que refleja la desproporci\u00f3n incoherencia y trato desigual que le imprime el precepto normativo demandado a los funcionarios de la polic\u00eda que ostentan el grado de PATRULLEROS frente a los policiales DEL MISMO NIVEL EJECUTIVO para quienes no interesa si fueron sancionados en los \u00faltimos tres (3) a\u00f1os situaci\u00f3n que pone de relieve y de manera objetiva la discriminaci\u00f3n injustificada.\u201d30 \u00a0<\/p>\n<p>Adicionalmente, el actor sostuvo: \u201cde igual manera el propio art\u00edculo 21 ibidem, regula el tema del ascenso para oficiales, y suboficiales, sin embargo a ninguno de ellos se les impuso la exigencia de no haber sido sancionado [sic] en los \u00faltimos tres (3) a\u00f1os, situaci\u00f3n que rompe el trato igual para el personal de la Polic\u00eda Nacional.\u201d31 Todo lo anterior para justificar el cargo por violaci\u00f3n del principio de igualdad arg\u00fcido en la demanda, pues \u00e9ste considera que la norma en cuesti\u00f3n apareja un trato injustificadamente discriminatorio para los patrulleros en relaci\u00f3n, tanto con los dem\u00e1s miembros del nivel ejecutivo, como con el resto del personal de oficiales y suboficiales. Postura que es apoyada por el interviniente y por el Ministerio P\u00fablico. \u00a0<\/p>\n<p>A efectos de resolver el cargo planteado, corresponde a la Sala Plena de esta Corporaci\u00f3n determinar si la formulaci\u00f3n contenida en el numeral 4\u00b0 del par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto-Ley 1791 de 2000 apareja una trasgresi\u00f3n del art\u00edculo 13 constitucional, debido a que exige a los patrulleros, para el ascenso dentro la carrera policial, acreditar \u201cno haber sido sancionado[s] dentro de los \u00faltimas tres (3) a\u00f1os.\u201d En atenci\u00f3n a ese problema jur\u00eddico se har\u00e1n algunas consideraciones en relaci\u00f3n con la carrera de la Polic\u00eda Nacional, el r\u00e9gimen de ascenso dentro de la carrera de la Polic\u00eda Nacional, algunas consideraciones en relaci\u00f3n con el juicio de igualdad y finalmente el juicio de igualdad aplicable a las normas acusadas.\u00a0 \u00a0<\/p>\n<p>4. La carrera de la Polic\u00eda Nacional. \u00a0<\/p>\n<p>El art\u00edculo 125 de la Constituci\u00f3n Pol\u00edtica prescribe la carrera como regla general en \u00e1mbito de la funci\u00f3n p\u00fablica y al tiempo contiene una enunciaci\u00f3n b\u00e1sica de los cargos que se except\u00faan de la misma, a saber: los de elecci\u00f3n popular, libre nombramiento y remoci\u00f3n, los de trabajadores oficiales y los dem\u00e1s que determine la ley. \u00a0<\/p>\n<p>Hay, pues, una regla principal aplicable a la regulaci\u00f3n de la mayor\u00eda los empleos p\u00fablicos: la generalidad se sigue por la carrera administrativa como mandato cuya satisfacci\u00f3n se asegura mediante la reglamentaci\u00f3n del ingreso, ascenso y retiro de estos cargos a trav\u00e9s de un sistema normativo que propende por su edificaci\u00f3n objetiva y desprovista de visos de arbitrariedad.32 \u00a0<\/p>\n<p>Esa categor\u00eda presenta dos modalidades principales: la carrera general y la especial33, que al tiempo se subdivide de acuerdo con su origen, ora legal o constitucional. 34 Las dos primeras, la carrera general y la especial de origen legal \u2013ordinario y extraordinario-, o sistemas espec\u00edficos de carrera administrativa, est\u00e1n bajo la administraci\u00f3n y vigilancia de la Comisi\u00f3n Nacional del Servicio Civil por disposici\u00f3n del art\u00edculo 130 de la Carta y de la Ley 909 de 2004, respectivamente.\u00a0 \u00a0<\/p>\n<p>Como ejemplos de la carrera especial de origen constitucional tenemos: el de la Fuerza P\u00fablica, constituida por las Fuerzas Militares y la Polic\u00eda Nacional (art\u00edculos 217 y 218); el de la Fiscal\u00eda General de la Naci\u00f3n (art\u00edculo 253); el de la Rama Judicial del poder p\u00fablico (art\u00edculo 256, numeral 1\u00b0); el de la Contralor\u00eda General de la Rep\u00fablica (art\u00edculo 268 numeral 10\u00b0) y el de la Procuradur\u00eda General de la Naci\u00f3n (art\u00edculo 279).35\u00a0 \u00a0<\/p>\n<p>Es claro, por manifiesta disposici\u00f3n de la Carta, que la carrera de la Polic\u00eda Nacional es de las especiales, naturalmente, de origen constitucional.36 Ahora, aunque el art\u00edculo 218 superior atribuye al legislador la tarea de definir el r\u00e9gimen de carrera de la Polic\u00eda, ello siempre debe seguir el prop\u00f3sito constitucional de que la administraci\u00f3n p\u00fablica cuente con servidores altamente cualificados para asumir de manera profesional las importantes responsabilidades que la Constituci\u00f3n y las leyes han confiado a los organismo estatales37, objetivo acentuado trat\u00e1ndose de actividades de la envergadura de las asignadas a la Polic\u00eda Nacional, garante de la armon\u00eda para el ejercicio arm\u00f3nico de las libertades y derechos reconocidas a los civiles.\u00a0 \u00a0<\/p>\n<p>Con base en la concepci\u00f3n que de este organismo fij\u00f3 la Carta como \u201ccuerpo armado permanente de naturaleza civil, a cargo de la Naci\u00f3n, cuyo fin primordial es el mantenimiento de las condiciones necesarias para el ejercicio de los derechos y libertades p\u00fablicas, y para asegurar que los habitantes de Colombia convivan en paz\u201d38. La jurisprudencia de este Alto Tribunal ha sostenido de manera reiterada y coincidente que \u00e9ste es un \u00f3rgano civil, con funciones esencialmente preventivas, orientado a precaver la alteraci\u00f3n del orden p\u00fablico, y en cuyas din\u00e1micas no rige la l\u00f3gica castrense.39\u00a0 \u00a0<\/p>\n<p>Resulta palmario que para la adecuada ejecuci\u00f3n de las funciones a cargo de la Polic\u00eda Nacional, el Constituyente previ\u00f3 un r\u00e9gimen especial de carrera cuya elaboraci\u00f3n estar\u00eda a cargo del legislador, por mandato del art\u00edculo 218 constitucional, en consideraci\u00f3n a la singular naturaleza de este cuerpo armado. Sobre el particular se ha sostenido que \u201cdada la trascendencia que para un Estado democr\u00e1tico representan las funciones que desempe\u00f1a la Polic\u00eda Nacional, el legislador ha buscado establecer un sistema de carrera que permita garantizar a sus miembros los derechos que de ella se derivan, como el ingreso en igualdad de oportunidades para quienes aspiran a ser parte de esas instituciones, el ascenso en la carrera por m\u00e9ritos, aptitudes y capacidades, y el retiro del servicio por las causales establecidas en la Constituci\u00f3n, como son: la calificaci\u00f3n insatisfactoria en el desempe\u00f1o del empleo, por violaci\u00f3n del r\u00e9gimen disciplinario, o por las dem\u00e1s causales previstas por la Carta Pol\u00edtica o por la ley.\u201d40 \u00a0<\/p>\n<p>Precisamente con la finalidad de consolidar ese r\u00e9gimen han sido expedidas por el legislador ordinario y extraordinario m\u00faltiples disposiciones normativas. Inicialmente se trat\u00f3 de la Ley 62 de 1993, \u201cpor la cual se expiden normas sobre la Polic\u00eda Nacional, se crea un \u00a0establecimiento p\u00fablico de seguridad social y Bienestar para la Polic\u00eda Nacional, se crea la Superintendencia de Vigilancia y Seguridad Privada y se reviste de facultades extraordinarias al Presidente de la Rep\u00fablica.\u201d En ella se le describi\u00f3 como \u201cun cuerpo armado, instituido para prestar un servicio p\u00fablico de car\u00e1cter permanente, de naturaleza civil y a cargo de la Naci\u00f3n. Su fin primordial es el mantenimiento de las condiciones necesarias para el ejercicio de los derechos y libertades p\u00fablicas para asegurar la paz ciudadana.\u201d41 De acuerdo con esa normativa, la Polic\u00eda Nacional estar\u00eda integrada por oficiales, personal del nivel ejecutivo, suboficiales, agentes, alumnos, quienes prestan el servicio militar obligatorio en la instituci\u00f3n y los servidores p\u00fablicos no uniformados pertenecientes a la misma. \u00a0<\/p>\n<p>A fin de regular la carrera profesional de los oficiales, suboficiales y personales de nivel ejecutivo adscritos a la Polic\u00eda Nacional, el numeral 1\u00b0 del art\u00edculo 35 de la Ley 62 de 1993 otorg\u00f3 facultades extraordinarias al Presidente de la Rep\u00fablica para su reglamentaci\u00f3n, que se intent\u00f3 mediante la expedici\u00f3n del respectivo decreto-ley, el 41 de 1994, que fue declarado inexequible en su mayor\u00eda por la Corte Constitucional mediante sentencia C-417 de 1994.42 \u00a0<\/p>\n<p>La declaratoria de inconstitucionalidad de las normas acusadas se fund\u00f3 en que, a falta de regulaci\u00f3n espec\u00edfica sobre la categor\u00eda de los agentes, el Ejecutivo omiti\u00f3 la obligaci\u00f3n conferida en el numeral 1\u00ba del art\u00edculo 35 de la norma habilitante, la ley 62 de 1993, que le exig\u00eda \u201cmodificar las normas de carrera del personal de oficiales, suboficiales y agentes de la Polic\u00eda Nacional.\u201d43 De esta forma, dicha previsi\u00f3n fue desconocida por el Gobierno en ejercicio de su labor como legislador extraordinario, pues al regular \u00fanicamente lo concerniente a los oficiales y suboficiales de la Polic\u00eda Nacional, no se cumpli\u00f3 a la cabalidad con los precisos t\u00e9rminos fijados por el Congreso en la ley de habilitaci\u00f3n legislativa. Su inobservancia configur\u00f3 la inconstitucionalidad de casi todas las normas del decreto.\u00a0 \u00a0<\/p>\n<p>Con posterioridad se hizo un segundo esfuerzo por consolidar la carrera del nivel ejecutivo mediante la Ley 180 de 1995, \u201cpor la cual se modifican y expiden algunas disposiciones sobre la Polic\u00eda Nacional y del Estatuto para la Seguridad Social y Bienestar de la Polic\u00eda Nacional y se otorgan facultades extraordinarias al Presidente de la Rep\u00fablica para desarrollar la Carrera Pol\u00edtica denominada &#8220;Nivel Ejecutivo&#8221;, modificar normas sobre estructura org\u00e1nica, funciones espec\u00edficas, disciplina y \u00e9tica y evaluaci\u00f3n y clasificaci\u00f3n y normas de la Carrera Profesional de Oficinas, Suboficiales y Agentes.\u201d \u00a0<\/p>\n<p>A trav\u00e9s del art\u00edculo 7\u00b0 numeral 1\u00b0 de esa Ley se habilit\u00f3 igualmente a la Presidencia de la Rep\u00fablica, en cabeza del Ministerio de Defensa, para \u201c1. Desarrollar en la Polic\u00eda Nacional la Carrera Profesional del Nivel Ejecutivo a que se refiere el art\u00edculo 1o. de la presente Ley, a la cual podr\u00e1n vincularse Suboficiales, Agentes, personal no uniformado y de incorporaci\u00f3n directa.\u201d44\u00a0 \u00a0<\/p>\n<p>Claramente el objetivo perseguido por el Ejecutivo con la consolidaci\u00f3n de este nivel jer\u00e1rquico era lograr la absorci\u00f3n, dentro de esta categor\u00eda, de un n\u00famero plural de Suboficiales y Agentes a efectos de conseguir la optimizaci\u00f3n de la carrera policial, sistema para cuyo funcionamiento no se exig\u00eda hasta la fecha requisitos rigurosos para el acceso a cargos de planta, fundamentalmente para el ingreso al cargo de agente, que no estaba condicionado a la culminaci\u00f3n del bachillerato. \u00a0<\/p>\n<p>En raz\u00f3n de ello fue expedido el Decreto 132 de 1995, \u201cpor el cual se desarrolla la carrera profesional del Nivel Ejecutivo de la Polic\u00eda Nacional\u201d que result\u00f3 finalmente derogado por el art\u00edculo 95 del Decreto 1791 de 2000, que contiene las normas actualmente demandadas. En lo atinente al ingreso, justamente en ese af\u00e1n por cualificar la carrera policial, se estableci\u00f3 en el Decreto 132:\u00a0 \u00a0<\/p>\n<p>\u201cART\u00cdCULO 12. INGRESO DE SUBOFICIALES AL NIVEL EJECUTIVO.\u00a0Podr\u00e1n ingresar a la escala jer\u00e1rqu\u00edca del Nivel Ejecutivo de la Polic\u00eda Nacional, los suboficiales en servicio activo que lo soliciten, de acuerdo con las siguientes equivalencias: \u00a0<\/p>\n<p>1. Cabo segundo y Cabo Primero, al grado de Subintendente. \u00a0 \u00a0<\/p>\n<p>2. Sargento Segundo y Sargento Viceprimero, al grado de Intendente. \u00a0 \u00a0<\/p>\n<p>3. Sargento Primero, al grado de Subcomisario; \u00a0 \u00a0<\/p>\n<p>4. Sargento mayor, al grado de Comisario. \u00a0 \u00a0<\/p>\n<p>PAR\u00c1GRAFO 1o.\u00a0Una vez se ingrese al Nivel ejecutivo de la Polic\u00eda Nacional, se exigir\u00e1 el t\u00edtulo de bachiller, como requisito para ascensos posteriores, de acuerdo con la reglamentaci\u00f3n que expida la Direcci\u00f3n General de la Polic\u00eda Nacional (\u2026) \u00a0<\/p>\n<p>ART\u00cdCULO 13. INGRESO DE AGENTES AL NIVEL EJECUTIVO.\u00a0Podr\u00e1n ingresar al primer grado del Nivel Ejecutivo de la Polic\u00eda Nacional, los agentes en servicio activo siempre y cuando re\u00fanan los siguientes requisitos: \u00a0 \u00a0<\/p>\n<p>1. Solicitud escrita a la Direcci\u00f3n General de la Polic\u00eda Nacional. \u00a0<\/p>\n<p>2. Acreditar el t\u00edtulo de bachiller en cualquier modalidad. \u00a0<\/p>\n<p>3. Evaluaci\u00f3n y concepto favorable del Comit\u00e9 de Evaluaci\u00f3n del personal del Nivel Ejecutivo de la Polic\u00eda Nacional. \u00a0 \u00a0<\/p>\n<p>PAR\u00c1GRAFO 1o.\u00a0Los agentes en servicio activo que no sean bachilleres, tendr\u00e1n plazo de tres (3) a\u00f1os contados a partir de la vigencia del presente decreto, para acreditar este requisito, o en su defecto, deber\u00e1n adelantar y aprobar un curso de nivelaci\u00f3n acad\u00e9mica de acuedo [sic] con reglamentaci\u00f3n que expida la Direcci\u00f3n General de la Polic\u00eda Nacional. \u201d (Negrillas por fuera del texto original) \u00a0<\/p>\n<p>Resulta palmario que el objetivo perseguido con el establecimiento de este nuevo escalaf\u00f3n fue la profesionalizaci\u00f3n de la actividad policial y el fomento de las condiciones primordiales para la promoci\u00f3n del personal perteneciente a cargos de planta, mediante la fijaci\u00f3n de requisitos m\u00e1s rigurosos para el acceso a esos puestos b\u00e1sicos y la posibilidad subsecuente de que este personal tenga aseguradas mayores opciones de ascenso.\u00a0 \u00a0<\/p>\n<p>Como se dijo, la expedici\u00f3n del Decreto 1791 de 2000 implic\u00f3 la derogatoria de las normas que con anterioridad regulaban la carrera policial. Este result\u00f3 de la autorizaci\u00f3n dada por el legislador ordinario al Presidente de la Rep\u00fablica para la reglamentaci\u00f3n de esta tem\u00e1tica, en virtud el art\u00edculo 1\u00b0 de la Ley 578 de 2000 que dispuso:\u00a0 \u00a0<\/p>\n<p>\u201cART\u00cdCULO 1\u00b0. De conformidad con el numeral 10 del art\u00edculo 150 de la Constituci\u00f3n Pol\u00edtica, rev\u00edstese al Presidente de la Rep\u00fablica de precisas facultades extraordinarias, hasta por el t\u00e9rmino de seis (6) meses, contados a partir de la promulgaci\u00f3n de la presente ley, para expedir las normas de carrera, los reglamentos de r\u00e9gimen disciplinario y de evaluaci\u00f3n de los oficiales y suboficiales de las Fuerzas Militares; el reglamento de aptitud psicof\u00edsica, incapacidades, invalideces e indemnizaciones de las Fuerzas Militares y de la Polic\u00eda Nacional y el r\u00e9gimen de carrera y\/o estatuto del soldado profesional as\u00ed como el reglamento de disciplina y \u00e9tica para la Polic\u00eda Nacional, el reglamento de evaluaci\u00f3n y clasificaci\u00f3n para el personal de la Polic\u00eda Nacional, las normas de carrera del personal de oficial y suboficiales de la Polic\u00eda Nacional, las normas de carrera profesional del nivel ejecutivo de la Polic\u00eda Nacional, los estatutos del personal civil del Ministerio de Defensa y la Polic\u00eda Nacional; la estructura del sistema de salud de las Fuerzas Militares y de la Polic\u00eda Nacional\u201d45 \u00a0<\/p>\n<p>Este \u00faltimo decreto s\u00ed satisface el prop\u00f3sito de regular el nivel ejecutivo de la Polic\u00eda Nacional que, como ya fue expuesto, aparece delineado inicialmente en la Ley 180 de 1995, norma en la que se retoma la caracterizaci\u00f3n que de este cuerpo se consign\u00f3 en la Ley 62 de 1993. De tal forma se reafirma su composici\u00f3n por parte de oficiales, personal del nivel ejecutivo, suboficiales, agentes, alumnos, por quienes presten el servicio militar obligatorio en la instituci\u00f3n, as\u00ed como los servidores p\u00fablicos no uniformados que laboren en la misma.46\u00a0 \u00a0<\/p>\n<p>Cabe volver en este punto sobre la formulaci\u00f3n del art\u00edculo 7\u00ba de la Ley 180 que orden\u00f3 revestir de facultades extraordinarias al ejecutivo para &#8220;desarrollar en la Polic\u00eda Nacional una nueva carrera profesional, la del nivel ejecutivo, a la cual podr\u00edan vincularse Suboficiales, Agentes, personal no uniformado y de incorporaci\u00f3n directa.\u201d\u00a047 (Negrillas por fuera del texto original) \u00a0<\/p>\n<p>En efecto, de la Ley 180 se desprende el prop\u00f3sito inequ\u00edvoco de instaurar una nueva carrera profesional, que result\u00f3 regulada con la promulgaci\u00f3n del Decreto 1791 de 2000, en el cual se mantuvo la estructura jer\u00e1rquica inicialmente propuesta en la Ley 180, salvo por la categor\u00eda de los alumnos que prestan servicio en la instituci\u00f3n, la cual fue suprimida de esta estructura jer\u00e1rquica48. Conforme esta nueva normatividad, la carrera policial estar\u00eda integrada por cuatro categor\u00edas que en orden descendente ser\u00edan las siguientes: 1) oficiales, 2) nivel ejecutivo, 3) suboficiales y 4) agentes. A manera de ilustraci\u00f3n tenemos que los cargos que por disposici\u00f3n del Decreto 1791 de 2000 conforman la estructura policial podr\u00edan se organizan as\u00ed: \u00a0<\/p>\n<p>\u201c1. Oficiales \u00a0<\/p>\n<p>a) Oficiales Generales \u00a0<\/p>\n<p>1. General \u00a0<\/p>\n<p>2. Teniente General \u00a0<\/p>\n<p>3. Mayor General \u00a0<\/p>\n<p>4. Brigadier General \u00a0<\/p>\n<p>b) Oficiales Superiores \u00a0<\/p>\n<p>1. Coronel \u00a0<\/p>\n<p>2. Teniente Coronel \u00a0<\/p>\n<p>3. Mayor \u00a0<\/p>\n<p>c) Oficiales Subalternos \u00a0<\/p>\n<p>1. Capit\u00e1n \u00a0<\/p>\n<p>2. Teniente \u00a0<\/p>\n<p>3. Subteniente \u00a0<\/p>\n<p>2. Nivel Ejecutivo \u00a0<\/p>\n<p>a) Comisario \u00a0<\/p>\n<p>b) Subcomisario \u00a0<\/p>\n<p>c) Intendente Jefe \u00a0<\/p>\n<p>d) Intendente \u00a0<\/p>\n<p>e) Subintendente \u00a0<\/p>\n<p>f) Patrullero \u00a0<\/p>\n<p>3. Suboficiales \u00a0<\/p>\n<p>a) Sargento Mayor \u00a0<\/p>\n<p>b) Sargento Primero \u00a0<\/p>\n<p>c) Sargento Viceprimero \u00a0<\/p>\n<p>d) Sargento Segundo \u00a0<\/p>\n<p>e) Cabo Primero \u00a0<\/p>\n<p>f) Cabo Segundo \u00a0<\/p>\n<p>4. Agentes \u00a0<\/p>\n<p>a) Agentes del Cuerpo Profesional \u00a0<\/p>\n<p>b) Agentes del Cuerpo Profesional Especial\u201d49 \u00a0<\/p>\n<p>5. El r\u00e9gimen de ascenso dentro de la carrera de la Polic\u00eda Nacional. \u00a0<\/p>\n<p>Inicialmente es importante precisar que el Decreto 1791 de 2000 incluye en el cap\u00edtulo I del t\u00edtulo tercero dos normas que abren la posibilidad de que personal perteneciente a la categor\u00eda de suboficiales y agentes ingrese al nivel ejecutivo a manera de \u2018homologaci\u00f3n\u2019, simplemente mediante la presentaci\u00f3n de una solicitud escrita ante la Direcci\u00f3n General de la Polic\u00eda.\u00a0 \u00a0<\/p>\n<p>El art\u00edculo 9\u00ba, relativo al ingreso de suboficiales al nivel ejecutivo, precept\u00faa que \u201cpodr\u00e1n ingresar a la escala jer\u00e1rquica del Nivel Ejecutivo los suboficiales en servicio activo que lo soliciten, de acuerdo con las siguientes equivalencias: \u00a0<\/p>\n<p>1. Cabo Segundo y Cabo Primero, al grado de Subintendente; \u00a0<\/p>\n<p>2. Sargento Segundo, al grado de Intendente; \u00a0<\/p>\n<p>3. Sargento Viceprimero, al grado de Intendente Jefe; \u00a0<\/p>\n<p>4. Sargento Primero, al grado de Subcomisario; \u00a0<\/p>\n<p>5. Sargento Mayor, al grado de Comisario.\u201d50 \u00a0<\/p>\n<p>Por su parte, el art\u00edculo 10\u00ba, que regula lo propio para el personal agente dispone: \u201cpodr\u00e1n ingresar al primer grado del Nivel Ejecutivo, los agentes en servicio activo de acuerdo con las disposiciones que para tal efecto presente a consideraci\u00f3n del Ministro de Defensa Nacional el Director General de la Polic\u00eda Nacional.\u201d Ello quiere decir que los agentes que as\u00ed lo estimen conveniente cuentan con la posibilidad de ingresar al nivel ejecutivo en el primer grado, es decir, como patrulleros; mientras que los suboficiales, de acuerdo con esta escala de equiparaciones, entran a hacer parte del nivel ejecutivo en los cargos de subintendente, intendente, intendente en jefe, subcomisario y comisario. \u00a0<\/p>\n<p>La Sala ha de aclarar que de acuerdo con lo antedicho el decreto en cuesti\u00f3n prev\u00e9 una especie de esquema de equiparaci\u00f3n, lo que hace del ascenso una posibilidad estrictamente aplicable para el personal perteneciente al nivel ejecutivo y de oficiales, ya que los suboficiales y agentes, dentro del sistema de carrera, realmente encontrar\u00e1n una equivalencia en el nivel ejecutivo. Ello ha redundado en la desaparici\u00f3n paulatina del nivel de agentes y de suboficiales, objetivo principal de la consolidaci\u00f3n del nivel ejecutivo: lograr la mayor idoneidad del personal de base que integra la carrera de la polic\u00eda nacional. \u00a0<\/p>\n<p>Igualmente, cabe destacar que el ingreso al nivel ejecutivo \u2013por parte del personal no uniformado que pretende ingresar a la carrera policial o de los agentes y suboficiales que logran la homologaci\u00f3n- y al de oficiales est\u00e1 supeditado a la aprobaci\u00f3n de un curso de formaci\u00f3n,\u00a0 al que no es posible incorporarse a menos de que se acredite la satisfacci\u00f3n de los siguientes requisitos: \u201c1) ser colombiano; 2) ser bachiller, profesional universitario, tecn\u00f3logo o t\u00e9cnico, seg\u00fan el caso; 3) superar el proceso de admisi\u00f3n que la Direcci\u00f3n General de la Polic\u00eda Nacional presente para aprobaci\u00f3n del Ministro de Defensa Nacional; y 4) no haber sido condenado a penas privativas de la libertad, ni tener antecedentes disciplinarios.\u201d51 As\u00ed pues, quien pretenda ingresar al nivel ejecutivo y al nivel de oficiales deber\u00e1 demostrar, para efectos de acceder al curso de formaci\u00f3n respectivo, no haber sido condenado a penas privativas de la libertad ni tener antecedentes disciplinarios. \u00a0<\/p>\n<p>Ahora, es oportuno puntualizar que el art\u00edculo 20 del pluricitado Decreto 1791 introduce determinados par\u00e1metros generales para los ascensos al disponer que \u00e9stos \u201cse conferir\u00e1n a los oficiales, nivel ejecutivo y suboficiales en servicio activo que cumplan los requisitos establecidos, dentro del orden jer\u00e1rquico, de acuerdo con las vacantes existentes, conforme al Decreto de planta y con sujeci\u00f3n a las precedencias de la clasificaci\u00f3n que establece el Decreto de Evaluaci\u00f3n del Desempe\u00f1o.\u201d52 Es decir, que el ascenso de este personal presenta como condici\u00f3n general el lleno de los requerimientos contenidos en el Decreto de Evaluaci\u00f3n y Desempe\u00f1o, 1800 de 2000, y a la existencia de vacantes disponibles para la promoci\u00f3n, autorizadas por el Decreto de Planta.53 \u00a0<\/p>\n<p>Como condiciones generales para el ascenso tenemos, en primer lugar, la existencia de vacantes, de acuerdo con el respectivo Decreto de Planta.54 \u00a0Cuando el ascenso conduzca al ingreso al nivel ejecutivo y de oficiales, se deber\u00e1 atender el respectivo curso de formaci\u00f3n que, como ya fue explicado, no puede realizarse cuando el personal haya sido condenado a penas privativas de la libertad o presente antecedentes disciplinarios. De no tratarse del ingreso a estos niveles, sino del ascenso dentro de los mismos, en particular dentro de los cargos que le siguen al de subintendente \u2013 tomar el curso para ascenso es un requisito que no se exige cuando la promoci\u00f3n se da del cargo de patrullero al de subintendente-, se deber\u00e1 tomar el correspondiente curso para ascenso. El acceso a este curso est\u00e1 antecedido por una evaluaci\u00f3n parcial, y al t\u00e9rmino del mismo igualmente tendr\u00e1 lugar una evaluaci\u00f3n y clasificaci\u00f3n55, en atenci\u00f3n a lo dispuesto en el Decreto 1800 de 2000. \u00a0<\/p>\n<p>En el Decreto 1800 de 2000, \u201cpor el cual se dictan normas para la evaluaci\u00f3n del desempe\u00f1o del personal uniformado de la Polic\u00eda Nacional\u201d, se exponen las caracter\u00edsticas de este proceso que tiene como objetivos, al tenor de su art\u00edculo 4\u00ba, \u201cestablecer y valorar los logros de la gesti\u00f3n desarrollada por el personal en servicio activo de la Polic\u00eda Nacional, en un per\u00edodo determinado para formular perfiles ocupacionales y profesionales, establecer planes de capacitaci\u00f3n, otorgar est\u00edmulos y ascensos, facilitar la reubicaci\u00f3n laboral, asignar cargos y decidir sobre la permanencia en la Instituci\u00f3n.\u201d56 \u00a0<\/p>\n<p>Se precisa adem\u00e1s que el proceso de evaluaci\u00f3n comprende las etapas de \u201cconcertaci\u00f3n de la gesti\u00f3n, seguimiento, evaluaci\u00f3n, revisi\u00f3n y clasificaci\u00f3n del desempe\u00f1o personal y profesional.\u201d57Importante es subrayar que la clasificaci\u00f3n, \u00faltimo pelda\u00f1o del proceso evaluativo, est\u00e1 determinada por la valoraci\u00f3n del grado de desempe\u00f1o personal y profesional del aspirante. \u00a0<\/p>\n<p>Para el efecto, el Decreto plantea una escala de medici\u00f3n, instrumento a trav\u00e9s del cual se ubica al evaluado dentro del rango de clasificaci\u00f3n en atenci\u00f3n al valor num\u00e9rico asignado a su desempe\u00f1o durante el per\u00edodo de evaluaci\u00f3n respectivo. La respectiva medici\u00f3n se efect\u00faa con base en los siguientes criterios: \u00a0<\/p>\n<p>\u201c1. INCOMPETENTE: Es el evaluado que en su desempe\u00f1o personal y profesional no cumple con las acciones asignadas para el desarrollo de los procesos. Su calificaci\u00f3n est\u00e1 ubicada entre cero (0) y quinientos noventa y nueve (599) puntos y su rendimiento oscila entre cero por ciento (0%) y cuarenta y nueve por ciento (49%). El personal que sea clasificado en este rango ser\u00e1 retirado de la Instituci\u00f3n. \u00a0<\/p>\n<p>2. DEFICIENTE: Es el evaluado que en su desempe\u00f1o personal y profesional obtiene resultados por debajo de lo esperado dentro de los procesos a los que ha sido asignado. Amerita un seguimiento cercano y compromiso con su mejoramiento a corto plazo. Su calificaci\u00f3n se ubica entre seiscientos (600) y seiscientos noventa y nueve (699) puntos y su rendimiento oscila entre cincuenta por ciento (50%) y cincuenta y siete por ciento (57%). El personal que sea clasificado en este rango por dos per\u00edodos consecutivos de evaluaci\u00f3n anual ser\u00e1 retirado de la Instituci\u00f3n. \u00a0<\/p>\n<p>3. ACEPTABLE: Es el evaluado que en su desempe\u00f1o personal y profesional cumple con la mayor\u00eda de las acciones y procesos asignados, presentando algunas deficiencias que se pueden corregir. Su calificaci\u00f3n se ubica entre setecientos (700) y setecientos noventa y nueve (799) puntos y su rendimiento oscila entre cincuenta y ocho por ciento (58%) y sesenta y seis por ciento (66%). El personal que sea clasificado en este rango amerita observaci\u00f3n y refuerzo por parte del evaluador. \u00a0<\/p>\n<p>4. SATISFACTORIO: Esta calificaci\u00f3n se otorga al evaluado que en su desempe\u00f1o personal y profesional, obtiene los resultados esperados dentro de los procesos a los que ha sido asignado. Su calificaci\u00f3n se ubica entre ochocientos (800) y mil (1.000) puntos y su rendimiento oscila entre sesenta y siete por ciento (67%) y ochenta y tres por ciento (83%). El personal que sea clasificado en este rango amerita mejoramiento continuo y podr\u00e1 ser tenido en cuenta para participar en los planes de capacitaci\u00f3n que determine la Direcci\u00f3n General de la Polic\u00eda Nacional. \u00a0<\/p>\n<p>5. SUPERIOR: Es el evaluado que en su desempe\u00f1o personal y profesional, adem\u00e1s de obtener los resultados esperados dentro de los procesos asignados, realiza actividades o hechos sobresalientes. Su calificaci\u00f3n se ubica entre mil uno (1.001) y mil doscientos (1.200) puntos y su rendimiento oscila entre ochenta y cuatro por ciento (84%) y cien por ciento (100%). El personal que sea clasificado en este rango, amerita ser tenido en cuenta para participar en los planes de est\u00edmulos que determine la Direcci\u00f3n General de la Polic\u00eda Nacional. \u00a0<\/p>\n<p>6. EXCEPCIONAL: Es el evaluado que en su desempe\u00f1o personal y profesional, adem\u00e1s de obtener los resultados esperados dentro de los procesos asignados, realiza actividades o hechos que tienen trascendencia institucional. Su calificaci\u00f3n est\u00e1 ubicada entre mil doscientos uno (1.201) y mil cuatrocientos (1.400) puntos y su rendimiento es del cien por ciento (100%) en adelante. El personal que sea clasificado en este rango, amerita ser tenido en cuenta para participar en los planes de est\u00edmulos que determine la Direcci\u00f3n General de la Polic\u00eda Nacional.\u201d58 \u00a0<\/p>\n<p>Conforme estos m\u00e1rgenes de evaluaci\u00f3n, se lleva a cabo la clasificaci\u00f3n para ascenso que est\u00e1 dada por el promedio de las valoraciones anuales hechas en relaci\u00f3n con un interesado durante el tiempo de permanencia en el grado respectivo, ejercicio que deriva en la ubicaci\u00f3n del evaluado dentro de la disposici\u00f3n para ascenso.59 Como se dijo, tales valores ser\u00e1n fijados con base en el desempe\u00f1o profesional y personal del polic\u00eda, determinaci\u00f3n que comprende un juicio en \u00a0relaci\u00f3n con sus aptitudes, grado de capacitaci\u00f3n, gesti\u00f3n e idoneidad \u00e9tica y disciplinaria. \u00a0<\/p>\n<p>Este Decreto compendia en su art\u00edculo 47, sobre clasificaci\u00f3n para el ascenso, una serie de hip\u00f3tesis que imposibilitan su concreci\u00f3n, a saber: \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Quien quede clasificado en la escala de medici\u00f3n en el rango de &#8220;Deficiente&#8221;, en el \u00faltimo a\u00f1o de su grado para ascenso, no podr\u00e1 ascender y quedar\u00e1 en observaci\u00f3n durante un (1) a\u00f1o, al t\u00e9rmino del cual deber\u00e1 obtener como m\u00ednimo una clasificaci\u00f3n en el rango de &#8220;Aceptable&#8221; para poder ascender. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Cuando el promedio aritm\u00e9tico de las evaluaciones para ascenso ubique al evaluado en la escala de medici\u00f3n en el rango de &#8220;Deficiente&#8221;, no podr\u00e1 ascender y quedar\u00e1 en observaci\u00f3n durante un (1) a\u00f1o, al t\u00e9rmino del cual deber\u00e1 obtener como m\u00ednimo una clasificaci\u00f3n en el rango de &#8220;Aceptable&#8221;. \u00a0 \u00a0<\/p>\n<p>Adicionalmente, el numeral tercero de ese mismo art\u00edculo plantea un condicionante importante, a saber, que \u201cel evaluado que se encuentre detenido, que tenga pendiente resoluci\u00f3n acusatoria dictada por autoridad judicial competente o que est\u00e9 sometido a investigaci\u00f3n disciplinaria por faltas, que de conformidad con las normas de Disciplina y \u00e9tica de la Polic\u00eda Nacional tengan naturaleza de grav\u00edsimas, \u00a0no se clasifica para ascenso\u201d (Negrillas y subrayas por fuera del texto original)60 Es m\u00e1s, la norma culmina con la previsi\u00f3n de que \u00fanicamente podr\u00e1 clasificar para el ascenso quien resulte absuelto frente a cualquiera \u00a0de las anteriores circunstancias. Es decir que hay un grado importante de verificaci\u00f3n en cuanto a la probidad del personal de polic\u00eda ya que, como supuesto para el ingreso al nivel ejecutivo y el de oficiales, se tiene que el personal no haya \u00a0sido condenado a penas privativas de la libertad o haya tenido antecedentes disciplinarios; y una vez dentro, los ascensos est\u00e1n circunscritos a la clasificaci\u00f3n propiamente dicha y a la realizaci\u00f3n de cursos de ascenso antes y despu\u00e9s de los cuales es menester igualmente la evaluaci\u00f3n y clasificaci\u00f3n del personal, excepto cuando se trata de los patrulleros que aspiran al cargo de subintendentes, quienes no tienen requisito para el ascenso la realizaci\u00f3n de tales cursos. \u00a0<\/p>\n<p>De vuelta al art\u00edculo 47 del Decreto 1800 de 2000, su constitucionalidad fue objeto de estudio mediante sentencia C-1156 de 2003, a trav\u00e9s de la cual se precis\u00f3 el alcance de cada uno de los t\u00e9rminos incluidos en dicha formulaci\u00f3n, as\u00ed: \u00a0<\/p>\n<p>\u201ci) Que se encuentre detenido &#8211; ha de entenderse preventivamente- en los t\u00e9rminos de los art\u00edculos 355 a 357 del C\u00f3digo de Procedimiento Penal (y en consecuencia por delitos que tengan prevista pena de prisi\u00f3n cuyo m\u00ednimo sea o exceda de cuatro a\u00f1os o que se encuentren en el listado que establece el art\u00edculo 357 del mismo C\u00f3digo), as\u00ed como en los t\u00e9rminos del art\u00edculo 529 del C\u00f3digo Penal Militar (es decir por delitos que en dicha normativa tengan prevista pena de prisi\u00f3n cuyo m\u00ednimo sea o exceda de dos a\u00f1os o cuando se trate de delitos que atenten contra el servicio o la disciplina, cualquiera que sea la sanci\u00f3n privativa de la libertad). \u00a0<\/p>\n<p>ii) que tenga pendiente resoluci\u00f3n acusatoria dictada por autoridad judicial competente. Es decir en los t\u00e9rminos de los art\u00edculos 397 y 398 del C\u00f3digo de Procedimiento Penal, o de los art\u00edculos 556 y 557 del C\u00f3digo Penal Militar que dicha resoluci\u00f3n acusatoria se encuentre en firme.\u00a0 \u00a0<\/p>\n<p>iii) que est\u00e9 sometido a investigaci\u00f3n disciplinaria por faltas que tengan naturaleza de grav\u00edsimas de conformidad con las normas de disciplina y \u00e9tica de la Polic\u00eda Nacional. Es decir aquellas conductas a las que alude el art\u00edculo 37 del Decreto 1798 de 2000, en relaci\u00f3n con las cuales se haya proferido un pliego de cargos que se encuentre ejecutoriado.\u201d61\u00a0 \u00a0<\/p>\n<p>De todas formas, de acuerdo con el art\u00edculo 66 del Decreto 1791 de 2000, \u201cel personal [que] sea condenado por sentencia ejecutoriada a la pena principal de prisi\u00f3n\u00a0o arresto, por la Justicia Penal Militar o por la Ordinaria, por delitos dolosos\u201d62, lo que redundar\u00eda en su destituci\u00f3n absoluta del cuerpo de la Polic\u00eda Nacional y la imposibilidad de volver a pertenecer al mismo. Esta formulaci\u00f3n es la que conlleva a la interpretaci\u00f3n de que la sanci\u00f3n a la que hace referencia la norma demandada, no obstante su aparente indeterminaci\u00f3n, debe entenderse como una de orden disciplinario, ya que una condena a pena principal de prisi\u00f3n o arresto por delitos dolosos conduce a la separaci\u00f3n absoluta del servicio, lo que no podr\u00eda constituir en esta medida, un requisito inhabilitante para el ascenso. La sanci\u00f3n de que trata la norma demandada es, entonces, una de naturaleza disciplinaria. \u00a0<\/p>\n<p>La constitucionalidad de la expresi\u00f3n \u201carresto\u201d comprendida en este art\u00edculo fue valorada mediante sentencia C-421 de 2002, en la cual se resolvi\u00f3 la exequibilidad de la misma con base en argumentos que, dada su trascendencia para la resoluci\u00f3n de esta controversia, ser\u00e1n reproducidas in extenso: \u00a0<\/p>\n<p>\u201cEn este sentido la Corporaci\u00f3n constata que con la disposici\u00f3n acusada el legislador, partiendo de las formulaciones constitucionales, tom\u00f3 en cuenta el car\u00e1cter civil del personal de polic\u00eda y que la finalidad que persigue al incluir el arresto por delitos dolosos como causal de separaci\u00f3n de la carrera en la Polic\u00eda Nacional y no hacer lo mismo en las Fuerzas Militares, radica en la necesidad de exigir una mayor pulcritud en el comportamiento de los miembros de la polic\u00eda dada su misi\u00f3n relacionada con el mantenimiento, entre la sociedad civil, de las condiciones necesarias para el ejercicio de los derechos fundamentales y la convivencia pac\u00edfica. (C.P art. 218). \u00a0Al respecto debe tomarse en cuenta \u00a0que la labor de la Polic\u00eda \u00a0es esencialmente preventiva \u00a0e implica un contacto m\u00e1s directo con la ciudadan\u00eda, \u00a0lo que obliga a extremar las medidas tendientes a proteger a la poblaci\u00f3n civil. \u00a0<\/p>\n<p>As\u00ed mismo no escapa a la Corte la voluntad del Legislador extraordinario de hacer m\u00e1s exigentes los requisitos de permanencia en la Polic\u00eda Nacional en el marco de la pol\u00edtica de moralizaci\u00f3n de la instituci\u00f3n, sometida en los \u00faltimos a\u00f1os a un complejo proceso \u00a0de reestructuraci\u00f3n, dentro del que \u00a0figuran \u00a0como unos de sus principales derroteros los de rescatar la credibilidad de la ciudadan\u00eda en la instituci\u00f3n \u00a0y fortalecer el compromiso \u00e9tico de sus miembros.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Para la Corte, estos objetivos que resultan plenamente compatibles con la Carta (arts. 2, 209, 218 C.P.), encuentran en la norma acusada un claro \u00a0instrumento para ser realizados, dado que \u00e9sta establece efectivamente un mayor nivel de exigencia al personal de la Polic\u00eda que limita las posibilidades de corrupci\u00f3n, al tiempo que protege a los ciudadanos que entran en contacto con ella. \u00a0 \u00a0<\/p>\n<p>La expresi\u00f3n que se impugna atiende entonces a una evidente voluntad del legislador extraordinario de fortalecer y consolidar el proceso de modernizaci\u00f3n de una de las instituciones m\u00e1s importantes \u00a0para el mantenimiento de \u00a0la convivencia y la garant\u00eda del libre ejercicio de los derechos y libertades p\u00fablicas que no puede \u00a0ser desconocida por esta Corporaci\u00f3n.\u201d63 (Negrillas por fuera del texto original) \u00a0<\/p>\n<p>Al margen de las sanciones penales, los funcionarios de la Polic\u00eda Nacional tambi\u00e9n pueden ser sancionados, en tanto empleados p\u00fablicos, por faltas disciplinarias, de la forma en que establecen la Ley 734 de 2000, \u201cpor la cual se expide el C\u00f3digo Disciplinario \u00danico\u201d, y en la Ley 1015 de 2006, \u201cpor medio de la cual se expide el R\u00e9gimen Disciplinario para la Polic\u00eda Nacional.\u201d \u00a0<\/p>\n<p>Al tenor de esta \u00faltima norma son destinatarios de este r\u00e9gimen disciplinario, tanto el personal uniformado escalafonado \u00a0como los Auxiliares de Polic\u00eda que est\u00e9n prestando servicio militar en este cuerpo civil, a\u00fan si se encuentran retirados. Igualmente se precisa que estas faltas disciplinarias pueden ser clasificadas como grav\u00edsimas, graves o leves64 y pueden acarrear las siguientes modalidades de sanciones: \u00a0<\/p>\n<p>\u201c1. Destituci\u00f3n e Inhabilidad General: \u00a0<\/p>\n<p>La Destituci\u00f3n consiste en la terminaci\u00f3n de la relaci\u00f3n del servidor p\u00fablico con la Instituci\u00f3n Policial; la Inhabilidad General implica la imposibilidad para ejercer la funci\u00f3n p\u00fablica en cualquier cargo o funci\u00f3n, por el t\u00e9rmino se\u00f1alado en el fallo, y la exclusi\u00f3n del escalaf\u00f3n o carrera.65 \u00a0<\/p>\n<p>2. Suspensi\u00f3n e Inhabilidad Especial: \u00a0<\/p>\n<p>La Suspensi\u00f3n consiste en la cesaci\u00f3n temporal en el ejercicio del cargo y funciones sin derecho a remuneraci\u00f3n; la Inhabilidad Especial implica la imposibilidad de ejercer funciones p\u00fablicas en cualquier cargo, por el t\u00e9rmino se\u00f1alado en el fallo. \u00a0<\/p>\n<p>3. Multa: \u00a0<\/p>\n<p>Es una sanci\u00f3n de car\u00e1cter pecuniario, que consiste en imponer el pago de una suma de dinero del sueldo b\u00e1sico devengado al momento de la comisi\u00f3n de la falta. \u00a0<\/p>\n<p>4. Amonestaci\u00f3n Escrita: \u00a0<\/p>\n<p>Consiste en el reproche de la conducta o proceder, por escrito, que debe registrarse en la hoja de vida.\u201d66 \u00a0<\/p>\n<p>Esta previsi\u00f3n tambi\u00e9n tiene incidencia en las posibilidades de promoci\u00f3n del personal que integra la carrera de la Polic\u00eda Nacional, en vista de que las sanciones disciplinarias de destituci\u00f3n y suspensi\u00f3n al tener como consecuencia, de un lado la terminaci\u00f3n definitiva de la relaci\u00f3n del servidor p\u00fablico, y de otro, la cesaci\u00f3n temporal de la misma, en la pr\u00e1ctica hacen mella en el c\u00e1lculo del tiempo que un polic\u00eda debe acreditar como requisito para ascender al cargo inmediatamente superior, pues para el efecto la normatividad pertinente fija unas fechas colectivas y definitivas de ascenso.67 \u00a0<\/p>\n<p>Hechas las anteriores anotaciones en relaci\u00f3n con los factores generales que restringen las posibilidades de ascenso del personal del nivel ejecutivo y de oficiales \u2013que como ya se apunt\u00f3 son lo que propiamente ascienden-, la Sala har\u00e1 referencia a los criterios que en particular determinan el ascenso a favor del personal que pretende escalar en la carrera policial desde el cargo de subintendente en adelante \u2013inciso primero del art\u00edculo 21 del Decreto 1791 de 2000-, en contraste con los requisitos exigidos para el ascenso de los patrulleros al cargo de subintendentes \u2013numeral 4\u00ba del par\u00e1grafo 4\u00ba del art\u00edculo 21 del Decreto 1791 de 2000.- \u00a0<\/p>\n<p>Estos requisitos aparecen consagrados en el art\u00edculo 21 del Decreto 1791 de 2000 y otras normas concordantes. De acuerdo con el inciso 1\u00ba de esta norma, hay una serie de exigencias dispuestas para el ascenso del personal de oficiales, suboficiales y de nivel ejecutivo desde el grado de subintendente, que no fueron previstas para la regulaci\u00f3n de la promoci\u00f3n de los patrulleros que aspiran al cargo de subintendentes. \u00a0 \u00a0<\/p>\n<p>En primer lugar, en relaci\u00f3n con los aspectos concernientes al cargo analizado, la norma exige al aspirante ser llamado a curso (numeral 2\u00ba) lo que implica, como ya se explic\u00f3, que inicialmente se efect\u00fae una evaluaci\u00f3n favorable de la que resulte el llamamiento a curso, una vez concluido lo cual el aspirante estar\u00e1 igualmente sujeto a evaluaci\u00f3n y calificaci\u00f3n68 por parte de la respectiva Junta de Clasificaci\u00f3n y Evaluaci\u00f3n.69 Las escalas de medici\u00f3n correspondientes obedece a criterios de valoraci\u00f3n del desempe\u00f1o personal y profesional de los aspirantes lo que, naturalmente, involucra asuntos concernientes a sus habilidades t\u00e9cnicas y acad\u00e9micas as\u00ed como de naturaleza disciplinaria. \u00a0<\/p>\n<p>En segundo lugar se demanda por parte del interesado haber obtenido la clasificaci\u00f3n exigida para ascenso (numeral 5\u00ba) requisito que, se reitera, est\u00e1 igualmente encausado en la edificaci\u00f3n del m\u00e9rito como principio orientador de la carrera policial y de conformidad con lo cual quien obtenga una valoraci\u00f3n deficiente desde el punto de vista de su ejercicio personal y profesional no podr\u00e1 acceder al pretendido ascenso. De hecho, como se apunt\u00f3, la norma dispone que quien est\u00e9 detenido, tenga pendiente \u00a0resoluci\u00f3n acusatoria o est\u00e9 sometido a investigaci\u00f3n disciplinaria por faltas grav\u00edsimas, no podr\u00e1 clasificar para ascenso. Por el contrario, \u201cen caso de resultar absuelto, previa clasificaci\u00f3n y reunir los dem\u00e1s requisitos, podr\u00e1 ascender con la misma antig\u00fcedad.\u201d70 As\u00ed pues, \u00e9sta constituye otra condici\u00f3n importante para asegurar la idoneidad del personal en ascenso, que es exigida para la promoci\u00f3n de patrulleros al cargo inmediatamente superior. \u00a0<\/p>\n<p>A m\u00e1s de lo anterior, la norma demanda un requisito que s\u00ed es com\u00fan al conjunto de condicionamientos para el ascenso de los patrulleros, pero que aparece reforzado en el caso de los Oficiales: el concepto favorable de la Junta de Clasificaci\u00f3n y Evaluaci\u00f3n, trat\u00e1ndose de todo el personal del nivel ejecutivo, y de la Junta Asesora del Ministerio de Defensa, en relaci\u00f3n con los miembros del nivel de oficiales.\u00a0 \u00a0<\/p>\n<p>En concordancia con lo anterior, el art\u00edculo 22 del Decreto 1791 de 2000 prescribe la realizaci\u00f3n de una evaluaci\u00f3n de la trayectoria profesional a cargo de las Juntas de Evaluaci\u00f3n y Clasificaci\u00f3n que tienen, en este sentido, las funciones de: i) evaluar la trayectoria policial para ascenso, ii) proponer al personal para ascenso y iii) recomendar la continuidad o retiro en el servicio policial. \u00a0<\/p>\n<p>Para mayor especificidad y rigorismo, el par\u00e1grafo de esta norma obliga a que para el ascenso a Brigadier General, la evaluaci\u00f3n de la trayectoria policial de los Coroneles sea llevada a cabo por una Junta de Generales, integrada por los Generales en servicio activo de la Polic\u00eda Nacional. En m\u00e1s, el ascenso a los cargos de Brigadieres y Generales depende de la libre determinaci\u00f3n del Gobierno Nacional, una vez librado el concepto respectivo por parte de la Junta Asesora para la Polic\u00eda Nacional, en el primer caso.71 Adem\u00e1s, el ascenso al grado de Oficial General no surtir\u00e1 efecto, por disposici\u00f3n del art\u00edculo 27 del Decreto en menci\u00f3n, hasta que su otorgamiento sea aprobado por parte del Senado de la Rep\u00fablica. \u00a0<\/p>\n<p>Las anteriores formulaciones normativas, que constituyen exigencias puntuales para el personal de oficiales, suboficiales y nivel ejecutivo desde el cargo de subintendente, develan la discordancia entre \u00e9ste y el r\u00e9gimen de ascenso de los patrulleros. \u00a0<\/p>\n<p>6. Algunas consideraciones en relaci\u00f3n con el juicio de igualdad. \u00a0<\/p>\n<p>De la forma en que ha sido formulado, derivan del principio de igualdad dos subreglas cuyo alcance ha sido interpretado por la doctrina y la jurisprudencia constitucional en el sentido de que, de un lado, existe un mandato de trato igual frente a todas aquellas situaciones f\u00e1ctica o jur\u00eddicamente equiparables siempre que no existan razones suficientes para proveer un trato diferente, y de otro lado, un mandamiento de trato desigual frente a circunstancias diferenciables. Tales contenidos esenciales surgen del art\u00edculo 13 constitucional, al tenor del cuyo inciso primero existe una obligaci\u00f3n de igualdad en la protecci\u00f3n, el trato y el goce de derechos, libertades y oportunidades, adem\u00e1s de una consecuente prohibici\u00f3n de discriminaci\u00f3n; mientras los incisos segundo y tercero contienen \u00a0mandatos espec\u00edficos de tratamiento diferenciado a favor de ciertos grupos marginados, discriminados o especialmente vulnerables. \u00a0<\/p>\n<p>De todas formas, sea cual fuera el sentido del juicio de igualdad alegado, \u00e9ste implica siempre un examen relacional que conlleva a la elaboraci\u00f3n de un ejercicio comparativo entre m\u00e1s de un extremo de una relaci\u00f3n. Por lo tanto, cuando se aduce la desigualdad de determinada normatividad es preciso su contraste con uno o m\u00e1s reg\u00edmenes jur\u00eddicos en lo que tiene que ver, generalmente, con aquellos aspectos que son relevantes desde el punto de vista de la finalidad de la diferenciaci\u00f3n.72\u00a0 \u00a0<\/p>\n<p>Es decir que, grosso modo, la igualdad constituye un concepto relativo, dado que la diferenciaci\u00f3n es predicable de aspectos puntuales susceptibles de confrontaci\u00f3n, mas no de las normas o supuestos abstractamente considerados, y comprende adem\u00e1s la valoraci\u00f3n de ambos preceptos am\u00e9n del principio de igualdad. Una vez fijados los extremos de la relaci\u00f3n, surge la obligaci\u00f3n de efectuar un estudio de razonabilidad de la medida en particular, cuyos lineamientos dependen de la naturaleza de la norma en cuesti\u00f3n. \u00a0<\/p>\n<p>As\u00ed que, el control de constitucionalidad en estos eventos no se reduce a la concreci\u00f3n de un juicio abstracto de igualdad entre la norma impugnada y el precepto que sirve de par\u00e1metro, sino que comprende un juicio particular sobre la proporcionalidad de la medida respectiva, objetivo para cuya consecuci\u00f3n se ha hecho uso del denominado test de igualdad. En otras palabras, este examen de igualdad consiste en \u201cestablecer, cu\u00e1les son las situaciones o supuestos que deben ser objeto de comparaci\u00f3n, desde el punto de vista objetivo o material y funcional, atendiendo todos los aspectos que sean relevantes en las respectivas relaciones o circunstancias, con el fin de determinar qu\u00e9 es lo igual que merece un trato igual y qu\u00e9 es lo divergente que exige, por consiguiente, un trato diferenciado. Realizado esto, es preciso determinar si el tratamiento que se dispensa en una situaci\u00f3n concreta obedece o no a criterios que sean objetivos, razonables, proporcionados y que est\u00e9n acordes con una finalidad constitucional leg\u00edtima.\u201d73 \u00a0<\/p>\n<p>Ahora, el referido examen adopta distintas modalidades \u2013leve, intermedio o estricto\u2013 seg\u00fan el grado de intensidad que demande la valoraci\u00f3n de la norma demandada, lo que a su vez obedece a la naturaleza de la materia regulada por la misma y sus implicaciones.74\u00a0 \u00a0<\/p>\n<p>As\u00ed, por ejemplo, el juicio leve es aplicable a medidas legislativas referidas a materias econ\u00f3micas, tributarias, de pol\u00edtica internacional o aquellas para cuya regulaci\u00f3n es competente, por expreso mandato constitucional, el legislador en ejercicio de su amplio margen de configuraci\u00f3n normativa. En este caso basta con que el fin buscado y el medio empleado no est\u00e9n constitucionalmente prohibidos, y que el instrumento edificado sea adecuado para la consecuci\u00f3n del fin propuesto. \u00a0<\/p>\n<p>En cuanto a esta hip\u00f3tesis, es decir que se trate de una materia plenamente librada al principio democr\u00e1tico y por ende sujeta a regulaci\u00f3n por parte del legislador, \u201cel juicio de igualdad es de car\u00e1cter d\u00e9bil, como quiera que s\u00f3lo debe verificarse que el trato diferenciado bajo an\u00e1lisis resulta adecuado para conseguir una finalidad permitida por la Constituci\u00f3n Pol\u00edtica. Dado que esta modalidad del juicio de igualdad se aplica sobre \u00e1mbitos donde el legislador goza de una amplia libertad de configuraci\u00f3n pol\u00edtica, el grado de intensidad del escrutinio que lleva a cabo el juez constitucional no puede ser de tal magnitud que termine por sustituir la funci\u00f3n que le corresponde desarrollar al Congreso como representante de la voluntad popular.\u201d75(Negrillas por fuera del texto original) \u00a0<\/p>\n<p>De otro lado, el juicio intermedio se destina a la valoraci\u00f3n de medidas legislativas con la virtualidad de afectar el goce de un derecho constitucional no fundamental o frente a circunstancias en las que se percibe un viso de arbitrariedad reflejado en las posibilidades de acceso a un derecho.76 Este juicio, que supone un an\u00e1lisis m\u00e1s riguroso, no s\u00f3lo comprende la determinaci\u00f3n de la conveniencia del medio, sino adem\u00e1s de su conducencia para la materializaci\u00f3n efectiva del fin perseguido con la norma que es objeto de estudio. \u00a0<\/p>\n<p>Por \u00faltimo, el juicio estricto envuelve el an\u00e1lisis de una medida que, por su mayor proximidad con derechos, valores y principios superiores, reclama un estudio \u00edntegro de proporcionalidad. De acuerdo con reiterada jurisprudencia constitucional \u00e9ste es procedente, en t\u00e9rminos esenciales cuando: 1) est\u00e1 de por medio una clasificaci\u00f3n sospechosa, tal como ocurre con aquellas basadas en las categor\u00edas prohibidas para hacer diferenciaci\u00f3n relacionadas en el inciso 1\u00ba del art\u00edculo 13 de la Constituci\u00f3n; 2) la medida afecta fundamentalmente a personas que se encuentran en condiciones de debilidad manifiesta, grupos marginados, sujetos discriminados, sectores sin acceso efectivo a la toma de decisiones o minor\u00edas insulares y discretas; 3) aparece prima facie que \u00a0la medida que hace la diferenciaci\u00f3n entre personas o grupos afecta gravemente el goce de un derecho constitucional fundamental; y 4) cuando la medida que es examinada es creadora de un privilegio. \u00a0<\/p>\n<p>En tales eventos es menester verificar la satisfacci\u00f3n de todos los elementos constitutivos de un juicio amplio de proporcionalidad, es decir, la necesidad, la razonabilidad y la proporcionalidad en sentido estricto de la medida respectiva.\u00a0 \u00a0<\/p>\n<p>De esta forma, la aplicaci\u00f3n del principio de proporcionalidad pretende la menor afectaci\u00f3n posible de los intereses jur\u00eddicos en juego con base en la adecuada configuraci\u00f3n de la relaci\u00f3n medio-fin, razonamiento que ha movido en ocasiones incluso a la modulaci\u00f3n de estos fallos de forma tal que no se recurra a la declaratoria de inexequibilidad de la disposici\u00f3n evaluada, sino a la eliminaci\u00f3n de la discriminaci\u00f3n derivada de la norma.77 \u00a0<\/p>\n<p>7. El juicio de igualdad aplicable a las disposiciones acusadas. \u00a0<\/p>\n<p>Como se explic\u00f3, el examen de constitucionalidad de una disposici\u00f3n por supuesta infracci\u00f3n del principio de igualdad exige una comparaci\u00f3n internormativa entre los supuestos de una norma y otra, para la posterior valoraci\u00f3n de la medida conforme el test de igualdad, en cualesquiera de sus modalidades, resultado de lo cual se establecer\u00e1 si la misma es o no una medida razonablemente discriminatoria. \u00a0<\/p>\n<p>Las formulaciones normativas que en este caso representan los extremos de la relaci\u00f3n comparativa integran el mismo art\u00edculo, el 21 del Decreto de la referencia, y precept\u00faan los requisitos para el ascenso de oficiales, suboficiales y nivel ejecutivo desde el grado de subteniente, de un lado, y para los patrulleros que pretendan ingresar como subintendentes, de otro. \u00a0<\/p>\n<p>Es palmario que entre los cargos superiores y m\u00e1s bajos de una escala jer\u00e1rquica hay distinciones que justifican precisamente esta estructura piramidal; razones de \u00edndole acad\u00e9mico, profesional y de experiencia en el campo motivan esta diferenciaci\u00f3n. Al respecto, a manera de ilustraci\u00f3n, se sostuvo en sentencia C-676 de 2001, reiterada en este sentido en la sentencia C-892 de 2003, que \u201cexiste una clara y directa relaci\u00f3n entre el nivel de preparaci\u00f3n de los miembros de la Fuerza P\u00fablica y el grado que ostentan en el escalaf\u00f3n correspondiente. Esta evidente correspondencia da cuenta de que los oficiales de la Polic\u00eda o de las Fuerzas Militares no se encuentran en igualdad de condiciones a los soldados, agentes y suboficiales de una y otra fuerza. Antes bien, el hecho de ocupar ese lugar en la jerarqu\u00eda castrense, denota -como se dijo- un nivel de preparaci\u00f3n superior que le otorga ciertos derechos de mando y decisi\u00f3n, los cuales no podr\u00edan ser desconocidos sin atentar, en tal caso s\u00ed, contra el principio de igualdad constitucional.\u201d78(Negrillas por fuera del texto original) \u00a0<\/p>\n<p>Sin embargo, establecer una relaci\u00f3n comparativa entre estos extremos normativos podr\u00eda ser admisible debido a que se trata de un asunto que concierne a todos los niveles que componen la carrera policial: los requisitos que deben condicionar el ascenso del personal que en estricto sentido goza de esta posibilidad, estos son, los Oficiales y el personal del Nivel Ejecutivo, ya que los agentes y los suboficiales simplemente est\u00e1n autorizados por el Decreto referido para obtener determinadas equivalencias dentro de la categor\u00eda del Nivel Ejecutivo y no propiamente un ascenso (art\u00edculos 9 y 10 del Decreto 1791 de 2000).\u00a0 \u00a0<\/p>\n<p>As\u00ed pues, las formulaciones bajo consideraci\u00f3n hacen referencia a los requisitos que deben condicionar la promoci\u00f3n dentro de la carrera policial con base en el m\u00e9rito como principio rector de la administraci\u00f3n p\u00fablica, lo que hace de estos enunciados normativos susceptibles de un juicio de igualdad. \u00a0<\/p>\n<p>Recordemos en este punto que el Constituyente previ\u00f3 a la Polic\u00eda Nacional como un cuerpo armado de naturaleza civil y con funciones esencialmente preventivas, encargado del mantenimiento de las condiciones apropiadas para el ejercicio de los derechos fundamentales y la convivencia pac\u00edfica. Por tal motivo su regulaci\u00f3n, en tanto carrera especial de origen constitucional, debe plantear exigencias r\u00edgidas, enfocadas a la garant\u00eda del m\u00e9rito policial, por la misi\u00f3n de este cuerpo y su grado de contacto con la sociedad.79 En esa medida, el margen de configuraci\u00f3n normativa autorizado al legislador presenta una talanquera especial generada por la naturaleza misma de la instituci\u00f3n como garante de la seguridad y armon\u00eda civil. \u00a0<\/p>\n<p>En raz\u00f3n de ello, como ya fue expuesto, las condiciones para ingreso, ascenso y retiro de la carrera policial se orientan por un prop\u00f3sito de \u00a0mantener la pulcritud y probidad de la instituci\u00f3n, lo que justifica el establecimiento de medidas orientadas a asegurar que el personal de polic\u00eda cumpla de la manera m\u00e1s decorosa posible su funci\u00f3n de guardar la armon\u00eda y convivencia ciudadanas. \u00a0<\/p>\n<p>REQUISITOS PARA EL ASCENSO DE OFICIALES, SUBOFICIALES Y NIVEL EJECUTIVO DESDE EL GRADO DE SUBINTENDENTE \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>REQUISITOS PARA QUE LOS PATRULLEROS INGRESEN COMO SUBINTENDENTES\u00a0 \u00a0\u00a0<\/p>\n<p>1. Tener el tiempo m\u00ednimo de servicio establecido para cada grado. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>2. Ser llamado a curso. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>3. Adelantar y aprobar los cursos de capacitaci\u00f3n establecidos por el Consejo Superior de Educaci\u00f3n Policial. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>4. Tener aptitud psicof\u00edsica de acuerdo con lo contemplado en las normas sobre Incapacidades e Invalideces. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>5. Obtener la clasificaci\u00f3n exigida para ascenso. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>6. Para oficiales, concepto favorable de la Junta Asesora del Ministerio de Defensa para la Polic\u00eda Nacional; para nivel ejecutivo y suboficiales, concepto favorable de la Junta de Evaluaci\u00f3n y Clasificaci\u00f3n. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>7. Hasta el grado de Coronel, acreditar un tiempo m\u00ednimo de dos (2) a\u00f1os en el respectivo grado, en labores operativas, de investigaci\u00f3n, docencia, desempe\u00f1o de funciones en la Gesti\u00f3n General del Ministerio de Defensa Nacional, de acuerdo con las disposiciones que para tal efecto presente a consideraci\u00f3n del Ministro de Defensa Nacional el Director General de la Polic\u00eda Nacional. \u00a0 \u00a0\u00a0<\/p>\n<p>8. Para el personal que permanezca en el Cuerpo Administrativo, acreditar un curso de actualizaci\u00f3n profesional en su especialidad, con una duraci\u00f3n no inferior a ciento veinte (120) horas. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Solicitud escrita a la Direcci\u00f3n General de la Polic\u00eda Nacional. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>2. Tener la aptitud sicof\u00edsica de acuerdo con las normas vigentes. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>3. Tener un tiempo m\u00ednimo de cinco (5) a\u00f1os de servicio en la Instituci\u00f3n como Patrullero. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>4. No haber sido sancionado en los \u00faltimos tres (3) a\u00f1os. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>5. Concepto favorable de la Junta de Clasificaci\u00f3n y Evaluaci\u00f3n respectiva. \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>6. El personal seleccionado deber\u00e1 adelantar y aprobar un curso de capacitaci\u00f3n cuya duraci\u00f3n no ser\u00e1 inferior a seis (6) meses. \u00a0<\/p>\n<p>En el extremo derecho del recuadro aparece subrayada la formulaci\u00f3n normativa que se estima discriminatoria respecto de la otra, en vista de que en la primera exige, para el ingreso en el cargo de subintendentes por parte del personal de patrulleros, el cumplimiento de un requisito que no \u00a0se prev\u00e9 para el ascenso en los cargos subsiguientes80: \u201cno haber sido sancionado en los \u00faltimos tres (3) a\u00f1os.\u201d81 \u00a0<\/p>\n<p>Entonces, mientras para ser promovido desde el cargo de subintendente no se exige la falta de sanci\u00f3n disciplinaria, para ascender de patrullero a subintendente s\u00ed se establece tal exigencia. No obstante eso no significa que los antecedentes disciplinarios no sean tenidos en cuenta pues es un criterio que debe ser evaluado por las Juntas respectivas al momento de disponer el llamamiento a curso de ascenso, al determinar la clasificaci\u00f3n para ascenso y al brindar el concepto correspondiente. \u00a0<\/p>\n<p>Pero ahora bien, el primer punto que debe ser examinado es si se trata de reg\u00edmenes jur\u00eddicos susceptibles de equiparaci\u00f3n. En efecto, como se explic\u00f3 en un ac\u00e1pite previo de la presente decisi\u00f3n actualmente existen al interior de la Polic\u00eda nacional pluralidad de formas de ingreso y de ascenso. \u00a0<\/p>\n<p>De acuerdo con lo dicho, es posible ingresar al cargo de patrullero acreditando el cumplimiento de los requisitos que aparecen en el art\u00edculo 8\u00b0 del Decreto 1791 de 2000, como condicionamientos generales para el ingreso dentro del nivel ejecutivo, o mediante el sistema de equivalencias, al pasar de agente al primer grado del nivel ejecutivo, de conformidad con el art\u00edculo 10\u00b0 del Decreto 1791 de 2000. Mientras que a los dem\u00e1s cargo de esta categor\u00eda se puede acceder, tanto en ascenso, como desde el grado de suboficial, mediante al sistema de equivalencias de que trata el art\u00edculo 9\u00b0 del mismo Decreto.\u00a0 \u00a0<\/p>\n<p>As\u00ed, un patrullero puede participar del concurso para ingresar a la carrera policial simplemente acreditando los siguientes requisitos: i) ser colombiano; ii) no haber sido condenado a penas privativas de la libertad, ni poseer antecedentes disciplinarios; iii) superar el proceso de selecci\u00f3n realizado por la Polic\u00eda Nacional; y iv) tener, como m\u00ednimo, t\u00edtulo de bachiller; superado lo cual deber\u00e1 \u201cadelantar y aprobar un curso de capacitaci\u00f3n cuya duraci\u00f3n no ser\u00e1 inferior a seis (6) meses\u201d82, para concretar el ingreso. Igualmente puede hacerlo, en calidad de agente o suboficial, mediante el referido sistema de equivalencias. Tambi\u00e9n fue posible, sin necesidad de participar en el concurso, trat\u00e1ndose del \u201cpersonal de patrulleros que a la entrada en vigencia del presente Decreto cumpl[\u00eda] antig\u00fcedad para ascenso hasta en el mes de septiembre del a\u00f1o 2001, sin perjuicio del cumplimiento de los dem\u00e1s requisitos que para el efecto exige la Ley.\u201d83 \u00a0<\/p>\n<p>A su vez, para ingresar a la carrera en calidad de agente se exig\u00eda, a partir del Decreto 262 de 1994, elevar una solicitud escrita a la Direcci\u00f3n General de la Polic\u00eda Nacional, acreditar el t\u00edtulo de bachiller en cualquier modalidad y obtener concepto favorable del Comit\u00e9 de Evaluaci\u00f3n del personal del nivel ejecutivo; pero con anterioridad, en vigencia del Decreto 1213 de 1990, en cuanto al grado de escolaridad los agente simplemente ten\u00edan que acreditar haber cursado y aprobado hasta el segundo grado de bachillerato.84 \u00a0<\/p>\n<p>En contraposici\u00f3n, puede acceder al cargo de subintendente, ora quien asciende desde el cargo de patrullero, o quien desde el cargo de suboficial logra la equivalencia en el nivel ejecutivo, lo que tendr\u00eda lugar \u201cen estricto orden de antig\u00fcedad en el grado.\u201d85 De acuerdo con la normatividad que regulaba el ingreso de suboficiales a la carrera policial, \u00e9stos podr\u00edan acceder a la Escuela de Formaci\u00f3n, siempre que tuvieran m\u00ednimo dos a\u00f1os de servicio activo en la Instituci\u00f3n en calidad de agentes y previo el lleno de los requisitos que estableciera para el efecto la Direcci\u00f3n General de la Polic\u00eda Nacional. \u00a0<\/p>\n<p>Ha de aclararse que una cosa es llegar al cargo de subintendente y otra ascender a partir de ah\u00ed a lo largo de la carrera policial. En vista de que el ingreso a este nivel siempre est\u00e1 condicionado al cumplimiento de, entre otros requisitos, \u201cno haber sido condenado a penas privativas de la libertad, ni tener antecedentes disciplinarios\u201d86, entendemos que para el Legislador resultaba trascendental que el acceso a los primeros escalafones de esta categor\u00eda \u2013ya fuera por parte del personal no uniformado o de los agentes y suboficiales beneficiados por las equivalencias- se hiciera sin antecedentes de esta \u00edndole pero, a\u00fan as\u00ed, \u00a0en adelante el factor disciplinario est\u00e1 impl\u00edcito en la en ascenso, por ser un factor determinante en las evaluaciones y clasificaciones a las que est\u00e1n sometidos todos los aspirantes en el proceso para obtener la promoci\u00f3n a partir del cargo de subintendente. \u00a0<\/p>\n<p>N\u00f3tese adem\u00e1s que el ingreso est\u00e1 regulado de forma distinta para uno u otro r\u00e9gimen. Las divergencias son igualmente evidentes en lo que tiene que ver con los reg\u00edmenes de ascenso aplicables para los patrulleros y para el resto del personal que integra la carrera.\u00a0 \u00a0<\/p>\n<p>Tal como se explic\u00f3, hay determinados requisitos particulares para el ascenso por parte del personal de oficiales y nivel ejecutivo a partir del cargo de subintendente, a saber: el llamamiento a curso,\u00a0 la clasificaci\u00f3n para ascenso y el concepto favorable de la Junta Asesora, trat\u00e1ndose de oficiales. Todos estos requerimientos, adem\u00e1s de ser mucho m\u00e1s \u00a0rigurosos, implican un seguimiento minucioso del desempe\u00f1o personal y profesional del aspirante, condiciones a las que no se ven sometidos los patrulleros que pretenden el ascenso al cargo de subintendentes.\u00a0 \u00a0<\/p>\n<p>En \u00faltimas, para regular las tem\u00e1ticas del ingreso y el ascenso por parte de los patrulleros y del resto del personal a que se refiere la norma, existe una pluralidad de reg\u00edmenes jur\u00eddicos que no pueden ser equiparados y cuyo dise\u00f1o, adem\u00e1s, correspondi\u00f3 a la libre configuraci\u00f3n normativa reconocida al legislador. Cabe reiterar que para la prosperidad de un juicio de igualdad se precisa la existencia de supuestos o situaciones que objetiva, material y funcionalmente sean equiparables, a fin de establecer \u2018qu\u00e9 es lo igual que merece un trato igual y qu\u00e9 es lo divergente que exige, por consiguiente, un trato diferenciado.\u201987Ante reg\u00edmenes tan dis\u00edmiles no hay lugar a un juicio de igualdad. En consecuencia, la formulaci\u00f3n demandada ser\u00e1 declara exequible por el cargo propuesto.\u00a0 \u00a0<\/p>\n<p>VII. DECISION \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Corte Constitucional, administrando justicia en nombre del pueblo y por mandato de la Constituci\u00f3n,\u00a0 \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>Primero: DECLARAR EXEQUIBLE el numeral 4\u00b0 del par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto-Ley 1791 de 2000 por el cargo propuesto.\u00a0 \u00a0<\/p>\n<p>C\u00f3piese, notif\u00edquese, comun\u00edquese, ins\u00e9rtese en la Gaceta de la Corte Constitucional y c\u00famplase. \u00a0<\/p>\n<p>JUAN CARLOS HENAO PEREZ \u00a0<\/p>\n<p>Presidente \u00a0<\/p>\n<p>MARIA VICTORIA CALLE CORREA \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>Ausente en comisi\u00f3n \u00a0<\/p>\n<p>MAURICIO GONZALEZ CUERVO \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>GABRIEL EDUARDO MENDOZA MARTELO \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>JORGE IVAN PALACIO PALACIO \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>NILSON ELIAS PINILLA PINILLA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>JORGE IGNACIO PRETELT CHALJUB \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>LUIS ERNESTO VARGAS SILVA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>MARTHA VICTORIA SACHICA MENDEZ \u00a0<\/p>\n<p>Secretaria General \u00a0 \u00a0<\/p>\n<p>1 Folio 9 del cuaderno principal. \u00a0<\/p>\n<p>2 Ibidem. \u00a0<\/p>\n<p>3 Folio 39 del cuaderno principal.\u00a0 \u00a0<\/p>\n<p>4 Folio 40 del cuaderno principal. \u00a0<\/p>\n<p>5 Ibidem. \u00a0<\/p>\n<p>6 Art\u00edculo 38 de la Ley 734 de 2002. \u00a0<\/p>\n<p>7 Folio 41 del cuaderno principal.\u00a0 \u00a0<\/p>\n<p>8 Folio 8 del cuaderno principal.\u00a0 \u00a0<\/p>\n<p>9 Folio 9 del cuaderno principal.\u00a0 \u00a0<\/p>\n<p>10 Folio 11 del cuaderno principal.\u00a0 \u00a0<\/p>\n<p>11 Op. Cit, folio 11. \u00a0<\/p>\n<p>12 Folio 12 del cuaderno principal.\u00a0 \u00a0<\/p>\n<p>13 Folio 18 del cuaderno principal.\u00a0 \u00a0<\/p>\n<p>14 Folio 23 del cuaderno principal.\u00a0 \u00a0<\/p>\n<p>15 Folio 24 del cuaderno principal.\u00a0 \u00a0<\/p>\n<p>16 Art\u00edculo 218 de la Constituci\u00f3n Pol\u00edtica. \u00a0<\/p>\n<p>17 Al respecto se citaron las sentencias C-444 de 1995 y C-525 de 1995. \u00a0<\/p>\n<p>18 Folio 82 del cuaderno principal. \u00a0<\/p>\n<p>19 Folio 82 del cuaderno principal. \u00a0<\/p>\n<p>20 Ibidem.\u00a0 \u00a0<\/p>\n<p>21 Folio 6 del cuaderno principal. \u00a0<\/p>\n<p>22 Ibidem.\u00a0 \u00a0<\/p>\n<p>23 Ibidem.\u00a0 \u00a0<\/p>\n<p>24 Folio 84 del cuaderno principal. \u00a0<\/p>\n<p>25 Se cit\u00f3 en este punto la sentencia C-078 de 2007. \u00a0<\/p>\n<p>26 Art\u00edculo 20 del Decreto 1791 de 2000. \u00a0<\/p>\n<p>27 Pues, de manera particular los numerales 7\u00ba y 8\u00ba exigen adem\u00e1s:\u00a0 \u00a0<\/p>\n<p>\u201c7. Hasta el grado de Coronel, acreditar un tiempo m\u00ednimo de dos (2) a\u00f1os en el respectivo grado, en labores operativas, de investigaci\u00f3n, docencia, desempe\u00f1o de funciones en la Gesti\u00f3n General del Ministerio de Defensa Nacional, de acuerdo con las disposiciones que para tal efecto presente a consideraci\u00f3n del Ministro de Defensa Nacional el Director General de la Polic\u00eda Nacional. \u00a0<\/p>\n<p>8. Para el personal que permanezca en el Cuerpo Administrativo, acreditar un curso de actualizaci\u00f3n profesional en su especialidad, con una duraci\u00f3n no inferior a ciento veinte (120) horas.\u201d \u00a0<\/p>\n<p>28 De acuerdo con el art\u00edculo 23 del Decreto 1791 de 2000, tiempos m\u00ednimos como requisito para ascender al Grado inmediatamente superior son los siguientes: \u00a0<\/p>\n<p>1. Oficiales \u00a0<\/p>\n<p>Teniente cuatro (4) a\u00f1os \u00a0<\/p>\n<p>Capit\u00e1n cinco (5) a\u00f1os \u00a0<\/p>\n<p>Mayor cinco (5) a\u00f1os \u00a0<\/p>\n<p>Teniente Coronel cinco (5) a\u00f1os \u00a0<\/p>\n<p>Coronel cinco (5) a\u00f1os \u00a0<\/p>\n<p>Brigadier General cuatro (4) a\u00f1os \u00a0<\/p>\n<p>Mayor General tres (3) a\u00f1os \u00a0<\/p>\n<p>Teniente General tres (3) a\u00f1os \u00a0<\/p>\n<p>2. Nivel Ejecutivo \u00a0<\/p>\n<p>Subintendente cinco (5) a\u00f1os \u00a0<\/p>\n<p>Intendente siete (7) a\u00f1os \u00a0<\/p>\n<p>Intendente Jefe cinco (5) a\u00f1os \u00a0<\/p>\n<p>Subcomisario cinco (5) a\u00f1os \u00a0<\/p>\n<p>3. Suboficiales \u00a0<\/p>\n<p>Cabo Segundo cuatro (4) a\u00f1os \u00a0<\/p>\n<p>Cabo Primero cuatro (4) a\u00f1os \u00a0<\/p>\n<p>Sargento Segundo cinco (5) a\u00f1os \u00a0<\/p>\n<p>Sargento Viceprimero cinco (5) a\u00f1os. \u00a0<\/p>\n<p>Sargento Primero cinco (5) a\u00f1os. \u00a0<\/p>\n<p>29 Numeral 6\u00ba del primer inciso del art\u00edculo 21 del Decreto 1791 de 2000. \u00a0<\/p>\n<p>30 Folio 9 del cuaderno principal. \u00a0<\/p>\n<p>31 Ibidem. \u00a0<\/p>\n<p>32 Sentencias C-195 de 1994, C-356 de 1994 y C-306 de 1995, entre otras. \u00a0<\/p>\n<p>33 Art\u00edculo 130 de la Constituci\u00f3n Pol\u00edtica. \u00a0<\/p>\n<p>34 Ver al respecto la sentencia C-1230 de 2005 en concordancia con el numeral 3\u00ba del art\u00edculo 4\u00ba de la Ley 909 de 2004. \u00a0<\/p>\n<p>35 La calidad de \u00e9stos como empleos pertenecientes a un r\u00e9gimen especial de carrera de origen constitucional ha sido sostenida \u00a0en sentencias como la C-391 de 1993, la C-356 de 1994 y la C-746 de 1999. \u00a0<\/p>\n<p>36 Art\u00edculo 218 de la Constituci\u00f3n Pol\u00edtica. \u00a0<\/p>\n<p>37 Ver al respecto, entre otras, las sentencias C-479 de 1992, C-195 de 1994 y C-1079 de 2002. \u00a0<\/p>\n<p>38 Art\u00edculo 218 de la Constituci\u00f3n Pol\u00edtica.\u00a0 \u00a0<\/p>\n<p>39 Sentencia C-024 de 1994 y C-453 de 1994. \u00a0<\/p>\n<p>40 Sentencia C-179 de 2006. \u00a0<\/p>\n<p>41 Art\u00edculo 5\u00b0 de la Ley 62 de 1993. \u00a0<\/p>\n<p>42 La parte resolutiva de la sentencia C-417 de 1994 reza:\u00a0 \u00a0<\/p>\n<p>\u201cPRIMERO: DECLARANSE INEXEQUIBLES LAS EXPRESIONES DEMANDADAS DE LOS ARTICULOS 1, 2, 3, 5, 6, 8, 9, 10, 11, 13, 14, 15, 16, 17, 21, 22, 24, 28, 29, 30, 31, 32, 33, 34, 35, 36, 37, 47, 48, 49, 54, 55, 56, 57, 58, 60, 61, 63, 64, 65, 66, 67, 70, 71, 72, 73, 74, 75, 76, 77, 80, 81, 82, 83, 84, 85, 86, 87, 88, 89, 90, 92, 93, 94, 95, 96, 97, 105, 107, 108, 112, 113 y 114 DEL DECRETO 41 DE 1994, POR EXCEDER EL LIMITE MATERIAL FIJADO EN LA LEY DE FACULTADES EXTRAORDINARIAS (62 DE 1993). \u00a0<\/p>\n<p>\u00a0SEGUNDO. DECLARANSE IGUALMENTE INEXEQUIBLES LOS ARTICULOS 18, 19, 20, 23 INCISO SEGUNDO, Y 79 INCISO SEGUNDO DEL DECRETO 41 DE 1994, POR LA MISMA RAZON.\u201d \u00a0<\/p>\n<p>43 Art\u00edculo 35 de la Ley 62 de 1993. \u00a0<\/p>\n<p>44 Numeral 1\u00ba del art\u00edculo 7\u00ba de la Ley 180 de 1995. \u00a0<\/p>\n<p>45 Art\u00edculo 1\u00b0 de la Ley 578 de 2000. \u00a0<\/p>\n<p>46 Art\u00edculo 1\u00ba de la Ley 180 de 1995. \u00a0<\/p>\n<p>47 Numeral \u00a01\u00ba del art\u00edculo 7\u00ba de la Ley 180 de 1995. \u00a0<\/p>\n<p>48 Textualmente el art\u00edculo 6 del referido decreto ordena: \u201cART\u00cdCULO 6o. ESTUDIANTES. Son estudiantes quienes ingresen a las seccionales de la Escuela Nacional de Polic\u00eda \u2018General Santander\u2019, para adelantar curso de formaci\u00f3n y no pertenecen a la jerarqu\u00eda de que trata el presente cap\u00edtulo.\u201d \u00a0<\/p>\n<p>49 Art\u00edculo 5\u00ba del Decreto 1791 de 2000. \u00a0<\/p>\n<p>50 Art\u00edculo 9\u00ba del Decreto 1791 de 2000. \u00a0<\/p>\n<p>51 Art\u00edculo 8\u00ba del Decreto 1791 de 2000. \u00a0<\/p>\n<p>52 Art\u00edculo 20 del Decreto 1791 de 2000. \u00a0<\/p>\n<p>53 Para el efecto cabe tener presente lo dispuesto en el art\u00edculo 3\u00ba del Decreto- Ley 1791 de 2000 de acuerdo con el cual la planta de personal de la Polic\u00eda Nacional \u201cser\u00e1 fijada \u00a0por el Gobierno Nacional, con base en las necesidades de la Instituci\u00f3n\u201d, lo que a su vez debe nutrirse con lo dispuesto en el decreto 4222 de 2006 -\u201cpor el cual se modifica parcialmente la Estructura del Ministerio de Defensa Nacional\u201d- en el que de manera precisa se ha fijado la estructura general de la Polic\u00eda Nacional y se han determinado las funciones particulares de cada una de las dependencias que la conforman. \u00a0 \u00a0<\/p>\n<p>54 Op. Cit., art\u00edculo 20 del Decreto 1791 de 2000. \u00a0<\/p>\n<p>55 De acuerdo con el art\u00edculo 20 del Decreto 1800 de 2000, hay dos clases de evaluaciones, una total y una parcial, y dentro de esta \u00faltima categor\u00eda se encuentra la evaluaci\u00f3n al t\u00e9rmino del curso para ascenso. \u00a0<\/p>\n<p>56 Art\u00edculo 4\u00ba del Decreto 1800 de 2000. \u00a0<\/p>\n<p>57 Art\u00edculo 13 del Decreto 1800 de 2000. \u00a0<\/p>\n<p>58 Art\u00edculo 42 del Decreto 1800 de 2000. \u00a0<\/p>\n<p>60 Numeral 3\u00ba del art\u00edculo 47 del Decreto 1800 de 2000. \u00a0<\/p>\n<p>61 Sentencia C-1156 de 2003. \u00a0<\/p>\n<p>62 Art\u00edculo 66 del Decreto 1791 de 2000. \u00a0<\/p>\n<p>63 Sentencia C-421 del 2002. \u00a0<\/p>\n<p>64 Art\u00edculo 33 de la Ley 1015 de 2006. \u00a0<\/p>\n<p>65 Este numeral concuerda con el art\u00edculo 61 del Decreto 1791 de 2000 que precept\u00faa: \u201cel personal ser\u00e1 destituido de la Polic\u00eda Nacional, cuando as\u00ed lo determine un fallo disciplinario debidamente ejecutoriado.\u201d \u00a0<\/p>\n<p>66 Art\u00edculo 38 de la Ley 1015 de 2006. \u00a0<\/p>\n<p>67 ART\u00cdCULO 24. FECHAS DE ASCENSOS.\u00a0Los ascensos de los oficiales se producir\u00e1n solamente en los meses de junio y diciembre y los del nivel ejecutivo y suboficiales en los meses de marzo y septiembre de cada a\u00f1o. Las disposiciones que confieren el primer grado dentro de la jerarqu\u00eda respectiva, podr\u00e1n dictarse en cualquier tiempo. \u00a0<\/p>\n<p>68 Op. Cit., art\u00edculo 13 del Decreto 1800 de 2000. \u00a0<\/p>\n<p>69 ARTICULO 49. CLASES DE JUNTAS.\u00a0Para efectos de Clasificaci\u00f3n y Evaluaci\u00f3n, se establecen las siguientes Juntas: \u00a0<\/p>\n<p>1. Para Oficiales \u00a0<\/p>\n<p>2. Para Suboficiales, Nivel Ejecutivo y Agentes. \u00a0<\/p>\n<p>70 Op. Cit., art\u00edculo 47 del Decreto 1800 de 2000. \u00a0<\/p>\n<p>71 Los art\u00edculo 25 y 26 del Decreto 1791 de 2000 respectivamente rezan: \u00a0<\/p>\n<p>ART\u00cdCULO 25. ASCENSO A BRIGADIER GENERAL.\u00a0Para ascender al grado de Brigadier General, el Gobierno, o\u00eddo el concepto de la Junta Asesora para la Polic\u00eda Nacional, escoger\u00e1 libremente entre los Coroneles, que hayan cumplido las condiciones que este Decreto determina y se hayan capacitado en los programas que para tal efecto establezca el Consejo Superior de Educaci\u00f3n Policial. \u00a0<\/p>\n<p>ART\u00cdCULO 26. ASCENSO DE GENERALES.\u00a0&lt;Art\u00edculo modificado por el art\u00edculo\u00a09\u00a0de la Ley 1405 de 2010. El nuevo texto es el siguiente:&gt; Para ascender a los Grados de Mayor General, Teniente General y General, el Gobierno Nacional escoger\u00e1 libremente entre los Brigadieres Generales, los Mayores Generales y Tenientes Generales, que re\u00fanan los requisitos establecidos en el presente decreto. \u00a0<\/p>\n<p>72 Sentencia C-1125 de 2008. \u00a0<\/p>\n<p>73 Sentencia C-654 de 1997. \u00a0<\/p>\n<p>74 Ver, entre otras, las sentencias C-404 de 2001, C-505 de 2001, C-579 de 2001, C-091 de 2003 y C- 180 de 2005.\u00a0 \u00a0<\/p>\n<p>75 Sentencia C-563 de 1997 \u00a0<\/p>\n<p>76 Sentencia C-227 de 2004. \u00a0<\/p>\n<p>77 Sentencia C-093 de 2001. \u00a0<\/p>\n<p>78 Sentencia C-676 de 2001. \u00a0<\/p>\n<p>79 Op. Cit., sentencia C-1156 de 2003. \u00a0<\/p>\n<p>80 Cabe recordar en este punto que acuerdo con este decreto la carrera policial estar\u00eda integrada de la siguiente forma: \u00a0<\/p>\n<p>1. Oficiales \u00a0<\/p>\n<p>a) Oficiales Generales \u00a0<\/p>\n<p>1. General \u00a0<\/p>\n<p>2. Teniente General \u00a0<\/p>\n<p>3. Mayor General \u00a0<\/p>\n<p>4. Brigadier General \u00a0<\/p>\n<p>b) Oficiales Superiores \u00a0<\/p>\n<p>2. Teniente Coronel \u00a0<\/p>\n<p>3. Mayor \u00a0<\/p>\n<p>c) Oficiales Subalternos \u00a0<\/p>\n<p>1. Capit\u00e1n \u00a0<\/p>\n<p>2. Teniente \u00a0<\/p>\n<p>3. Subteniente \u00a0<\/p>\n<p>2. Nivel Ejecutivo \u00a0<\/p>\n<p>a) Comisario \u00a0<\/p>\n<p>b) Subcomisario \u00a0<\/p>\n<p>c) Intendente Jefe \u00a0<\/p>\n<p>d) Intendente \u00a0<\/p>\n<p>e) Subintendente \u00a0<\/p>\n<p>f) Patrullero \u00a0<\/p>\n<p>3. Suboficiales \u00a0<\/p>\n<p>a) Sargento Mayor \u00a0<\/p>\n<p>b) Sargento Primero \u00a0<\/p>\n<p>c) Sargento Viceprimero \u00a0<\/p>\n<p>d) Sargento Segundo \u00a0<\/p>\n<p>e) Cabo Primero \u00a0<\/p>\n<p>f) Cabo Segundo \u00a0<\/p>\n<p>4. Agentes \u00a0<\/p>\n<p>a) Agentes del Cuerpo Profesional \u00a0<\/p>\n<p>b) Agentes del Cuerpo Profesional Especial \u00a0<\/p>\n<p>81 Numeral 4\u00ba del par\u00e1grafo 4\u00ba del art\u00edculo 21 del Decreto 1791 de 2000. \u00a0<\/p>\n<p>82 Inciso 2\u00b0 del par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto 1791 de 2000. \u00a0<\/p>\n<p>83 Inciso 3\u00b0 del par\u00e1grafo 4\u00b0 del art\u00edculo 21 del Decreto 1791 de 2000. \u00a0<\/p>\n<p>84 Art\u00edculo 9\u00b0 del Decreto 1213 de 1990. \u00a0<\/p>\n<p>85 Art\u00edculo 9\u00b0 del Decreto 1791 de 2000. \u00a0<\/p>\n<p>86 Op. Cit., art\u00edculo 8\u00b0 del Decreto 1791 de 2000. \u00a0<\/p>\n<p>87 Op. Cit., sentencia C-654 de 1997. \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia C-445\/11 \u00a0 CARGO DE SUBINTENDENTE EN LA POLICIA NACIONAL-Requisito de no haber sido sancionado en los \u00faltimos tres a\u00f1os para ascender, no constituye una vulneraci\u00f3n del derecho a la igualdad\u00a0 \u00a0 ASCENSO DE OFICIALES, NIVEL EJECUTIVO Y SUBOFICIALES DE LA POLICIA NACIONAL-Requisitos \u00a0 ASCENSO DE PATRULLERO AL CARGO DE SUBINTENDENTE-Condiciones\u00a0 \u00a0 CARRERA [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"class_list":["post-18389","post","type-post","status-publish","format-standard","hentry","category-sentencias-2011"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/18389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=18389"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/18389\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=18389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=18389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=18389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}