{"id":21696,"date":"2024-06-25T21:00:33","date_gmt":"2024-06-25T21:00:33","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/06\/25\/t-346a-14\/"},"modified":"2024-06-25T21:00:33","modified_gmt":"2024-06-25T21:00:33","slug":"t-346a-14","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-346a-14\/","title":{"rendered":"T-346A-14"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-346A-14 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia T-346A\/14 \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA \u00a0 ACTO ADMINISTRATIVO-Procedencia \u00a0 excepcional cuando amenaza derechos fundamentales\u00a0 \u00a0 \u00a0<\/p>\n<p>En amplia \u00a0 jurisprudencia la Corte Constitucional ha reiterado, por regla general, la \u00a0 improcedencia de la tutela como mecanismo para la protecci\u00f3n de derechos \u00a0 fundamentales que podr\u00edan ser vulnerados o amenazados como consecuencia de la \u00a0 expedici\u00f3n de un acto administrativo, cuyo control ata\u00f1e a la respectiva \u00a0 jurisdicci\u00f3n contenciosa. Con todo, pueden concurrir unas condiciones especiales \u00a0 que hacen procedente el amparo constitucional, si (i) de manera cierta emerge la \u00a0 amenaza o el da\u00f1o de magnitud sobre un derecho fundamental; (ii) que no exista \u00a0 forma de repararlo, de ocurrir, (iii) lo cual se aprecia inminente, (iv) \u00a0 convirtiendo en urgente e (v) impostergable e indispensable la protecci\u00f3n \u00a0 tutelar. \u00a0 \u00a0<\/p>\n<p>DERECHO FUNDAMENTAL A \u00a0 ESCOGER PROFESION U OFICIO-Contenido \u00a0 \u00a0<\/p>\n<p>El derecho a \u00a0 escoger profesi\u00f3n u oficio, consagrado en el art\u00edculo 26 superior, tiene que ser \u00a0 respetado, para que todas las personas puedan seleccionar libremente la \u00a0 actividad a la que van a dedicarse, de acuerdo con su vocaci\u00f3n, aptitud, \u00a0 habilidades e intereses, en condiciones de libertad e igualdad. \u00a0 \u00a0<\/p>\n<p>LIBERTAD DE \u00a0 ESCOGER PROFESION U OFICIO-L\u00edmites \u00a0 al exigir t\u00edtulo de idoneidad y obligaci\u00f3n de autoridades competentes de \u00a0 inspeccionar y vigilar el ejercicio de tales profesiones u oficios \u00a0 \u00a0<\/p>\n<p>No existiendo \u00a0 derechos absolutos, la libertad de escoger profesi\u00f3n u oficio tambi\u00e9n tiene \u00a0 l\u00edmites, derivados especialmente de dos aspectos relevantes: (i) la posibilidad \u00a0 que tiene el legislador de exigir t\u00edtulos de idoneidad, para el ejercicio de \u00a0 aquellas profesiones que exijan especial capacitaci\u00f3n y formaci\u00f3n acad\u00e9mica, \u00a0 cuya raigambre constitucional guarda relaci\u00f3n y fundamento en el deber de las \u00a0 autoridades p\u00fablicas de proteger los derechos ciudadanos y consultar el inter\u00e9s \u00a0 general; (ii) la obligaci\u00f3n de las autoridades p\u00fablicas competentes, de \u00a0 inspeccionar y vigilar el ejercicio de tales profesiones u oficios, conforme a \u00a0 las normas establecidas al efecto. Dichos l\u00edmites tienen reserva de ley, por lo \u00a0 que el legislador es el competente para establecer los diplomas de idoneidad que \u00a0 deben acompa\u00f1ar el ejercicio de las profesiones que los requieran y las \u00a0 condiciones en que se da la inspecci\u00f3n y vigilancia. As\u00ed, la exigencia de \u00a0 t\u00edtulos de idoneidad es una excepci\u00f3n, cuyo prop\u00f3sito es proteger a la comunidad \u00a0 del riesgo derivado de un ejercicio indebido, inid\u00f3neo o irresponsable de tal \u00a0 libertad. \u00a0 \u00a0<\/p>\n<p>PROFESION DE MEDICINA-Ejercicio implica \u00a0 un elevado riesgo social y un impacto significativo en los derechos de las \u00a0 personas \u00a0 \u00a0<\/p>\n<p>Reit\u00e9rese que la medicina es una actividad profesional cuya pr\u00e1ctica implica \u00a0 elevado riesgo social y un impacto significativo en los derechos de los \u00a0 asociados; consecuentemente, su ejercicio y el de sus diversas especialidades \u00a0 requieren t\u00edtulos de aptitud, que acrediten los conocimientos t\u00e9cnicos \u00a0 necesarios para la realizaci\u00f3n id\u00f3nea de las actividades correspondientes. \u00a0 Adem\u00e1s, las autoridades p\u00fablicas est\u00e1n habilitadas para vigilar e inspeccionar \u00a0 el ejercicio de tal profesi\u00f3n y sus especialidades, conforme a las exigencias \u00a0 normativas. \u00a0 \u00a0<\/p>\n<p>PROFESION DE ENDOSCOPISTA-Titulo de idoneidad \u00a0 \u00a0<\/p>\n<p>LIBERTAD DE \u00a0 ESCOGER PROFESION U OFICIO-No vulneraci\u00f3n por cuanto el accionante no posee \u00a0 t\u00edtulo especialista para ejercer la profesi\u00f3n de endoscopista \u00a0 \u00a0<\/p>\n<p>Referencia: \u00a0 expediente T-3991240. \u00a0 \u00a0<\/p>\n<p>Acci\u00f3n de tutela \u00a0 instaurada mediante apoderado por Germ\u00e1n Rivero Romero, contra el Ministerio de \u00a0 Salud y Protecci\u00f3n Social y la Secretar\u00eda de Salud de Boyac\u00e1. \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 Ponente: \u00a0 \u00a0<\/p>\n<p>NILSON PINILLA \u00a0 PINILLA \u00a0 \u00a0<\/p>\n<p>Bogot\u00e1, D. C., junio seis (6) de \u00a0 dos mil catorce (2014). \u00a0 \u00a0<\/p>\n<p>La Sala Sexta de Revisi\u00f3n de la \u00a0 Corte Constitucional, integrada por los Magistrados Nilson Pinilla Pinilla, \u00a0 Jorge Ignacio Pretelt Chaljub y Alberto Rojas R\u00edos, en ejercicio de sus \u00a0 competencias constitucionales y legales ha proferido la siguiente \u00a0 \u00a0<\/p>\n<p>SENTENCIA \u00a0 \u00a0<\/p>\n<p>En la revisi\u00f3n del fallo proferido \u00a0 en segunda instancia por Consejo de Estado, Sala de lo Contencioso \u00a0 Administrativo, Secci\u00f3n Cuarta, dentro de la acci\u00f3n de tutela instaurada \u00a0 mediante apoderado por Germ\u00e1n Rivero Romero, contra el Ministerio de Salud y \u00a0 Protecci\u00f3n Social y la Secretar\u00eda de Salud de Boyac\u00e1. \u00a0 \u00a0<\/p>\n<p>El asunto lleg\u00f3 a la Corte por remisi\u00f3n que realiz\u00f3 \u00a0 la secretar\u00eda de dicha Sala, en virtud de lo ordenado por el art\u00edculo 32 del \u00a0 Decreto 2591 de 1991; la Sala Cuarta de Selecci\u00f3n, por auto de abril 15 de 2013, \u00a0 lo eligi\u00f3 para revisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>I. ANTECEDENTES. \u00a0 \u00a0<\/p>\n<p>Mediante apoderado, el doctor Germ\u00e1n Rivero Romero, \u00a0 de 62 a\u00f1os de edad, inco\u00f3 acci\u00f3n de tutela en enero 24 de 2013, contra el \u00a0 Ministerio de Salud y Protecci\u00f3n Social y la Secretar\u00eda de Salud de Boyac\u00e1, \u00a0 pidiendo amparar sus derechos a la libre escogencia de profesi\u00f3n u oficio y al \u00a0 m\u00ednimo vital. \u00a0 \u00a0<\/p>\n<p>A. Hechos y relato contenido en \u00a0 la demanda. \u00a0 \u00a0<\/p>\n<p>1. El apoderado del actor se\u00f1al\u00f3 \u00a0 que su procurado obtuvo el t\u00edtulo profesional de doctor en medicina y cirug\u00eda en \u00a0 julio 9 de 1976, en la Pontificia Universidad Javeriana, y que entre enero y \u00a0 diciembre de 1991 particip\u00f3 en un entrenamiento en endoscopia digestiva, con \u00a0 pr\u00e1cticas supervisadas por dicha instituci\u00f3n (f. 1 cd. inicial), a partir de lo \u00a0 cual \u201cdesde hace m\u00e1s de 35 a\u00f1os ha ejercido la medicina diligentemente\u2026 y \u00a0 cuenta con pericia, experiencia, idoneidad y excelencia profesional en la \u00a0 realizaci\u00f3n de procedimientos de endoscopia durante 19 a\u00f1os\u201d (f. 5 ib.). \u00a0 \u00a0<\/p>\n<p>Indic\u00f3 que \u201clas condiciones \u00a0 para continuar trabajando como endoscopista cambiaron\u201d, con la Ley \u00a0 1164 de octubre 3 de 2007 (por la cual se dictan disposiciones en materia de \u00a0 talento humano en salud), pues frente a los presupuesto para el ejercicio de las \u00a0 profesiones y ocupaciones en esa \u00e1rea, el par\u00e1grafo 2\u00b0 del art\u00edculo 18 se\u00f1ala \u00a0 que \u201cquienes a la vigencia de la presente ley se encuentren ejerciendo \u00a0 competencias propias de especialidades, subespecialidades y ocupaciones del \u00e1rea \u00a0 de la salud sin el t\u00edtulo o certificado correspondiente, contar\u00e1n por una sola \u00a0 vez con un per\u00edodo de tres a\u00f1os para acreditar la norma de competencia acad\u00e9mica \u00a0 correspondiente expedida por una instituci\u00f3n legalmente reconocida por el \u00a0 Estado\u201d. \u00a0 \u00a0<\/p>\n<p>2. De otra parte, la realizaci\u00f3n \u00a0 de endoscop\u00edas de v\u00edas digestivas, seg\u00fan el anexo 1\u00b0 de la Resoluci\u00f3n 1043 de \u00a0 abril 3 de 2006 (\u201cpor la cual se establecen las condiciones que deben cumplir \u00a0 los prestadores de servicios de salud para habilitar sus servicios e implementar \u00a0 el componente de auditoria para el mejoramiento de la calidad de la atenci\u00f3n\u201d), \u00a0 qued\u00f3 a cargo de \u201cm\u00e9dicos especializados en gastroenterolog\u00eda, \u00a0 gastroenterolog\u00eda pedi\u00e1trica, pediatr\u00eda, coloproctolog\u00eda, cirug\u00eda pedi\u00e1trica, \u00a0 cirug\u00eda general con subespecialidad en gastroenterolog\u00eda que en su formaci\u00f3n \u00a0 demuestren bajo certificaci\u00f3n a excepci\u00f3n de los gastroenter\u00f3logos, \u00a0 gastroenter\u00f3logos pediatras o coloproct\u00f3logos haber recibido entrenamiento de un \u00a0 a\u00f1o en endoscopia de v\u00edas digestivas certificado por una Instituci\u00f3n de \u00a0 Educaci\u00f3n Superior reconocida por el Estado\u201d. \u00a0 \u00a0<\/p>\n<p>3. El apoderado del actor se\u00f1al\u00f3 \u00a0 que el doctor Germ\u00e1n Rivero Romero est\u00e1 en \u201cimposibilidad de realizar una de \u00a0 las especialidades exigidas, porque tratan de programas de extensa duraci\u00f3n \u00a0 (ninguno es menor de tres a\u00f1os y debe tenerse en cuenta que mi mandante a la \u00a0 fecha de promulgaci\u00f3n de la Ley ten\u00eda 62 a\u00f1os de edad), que tienen un precio muy \u00a0 elevado y para completar la dificultad del requisito, exigen dedicaci\u00f3n \u00a0 exclusiva, esto es, le impide al estudiante desempe\u00f1ar una actividad laboral \u00a0 paralelamente al estudio de la especializaci\u00f3n, lo cual es imposible de cumplir \u00a0 por mi mandante debido a su edad que hace que se trate de una persona que ya \u00a0 cuenta con una familia bajo su responsabilidad\u201d (f. 4 ib.). \u00a0 \u00a0<\/p>\n<p>Agreg\u00f3 que \u201cdesde el a\u00f1o 2010 \u00a0 dej\u00f3 de practicar los procedimientos de endoscopia, los cuales le reportaban un \u00a0 ingreso en promedio de OCHO MILLONES DE PESOS mensuales\u2026 con el cual pod\u00eda \u00a0 hacerle frente a la manutenci\u00f3n propia, de su n\u00facleo familiar y llevar una \u00a0 existencia en condiciones congruas\u201d (f. 8 ib.). Expres\u00f3 adem\u00e1s que \u00a0 \u201cdurante todo el tiempo que ha transcurrido desde que dej\u00f3 de practicar \u00a0 procedimientos de endoscopia, ha adelantado toda clase de actuaciones \u00a0 administrativas, tendientes a obtener la correspondiente habilitaci\u00f3n para \u00a0 realizar estos procedimientos de endoscopia sin que hasta la fecha\u2026 hayan \u00a0 permitido a mi mandante ejercer su profesi\u00f3n\u201d (f. 9 ib.). \u00a0 \u00a0<\/p>\n<p>4. As\u00ed, solicit\u00f3 inaplicar la \u00a0 preceptiva referida, \u201cdonde se establece la exigencia de tener un posgrado\u201d, \u00a0 para que pueda continuar efectuando endoscopias digestivas, pues cuenta con la \u00a0 idoneidad y experiencia para realizar esos procedimientos sin poner en riesgo \u00a0 vidas ni la salud p\u00fablica (fs. 21 a 22 ib.). \u00a0 \u00a0<\/p>\n<p>B. Documentos relevantes cuya \u00a0 copia obra en el expediente. \u00a0 \u00a0<\/p>\n<p>1. Poder otorgado por el doctor \u00a0 Germ\u00e1n Rivero Romero, para la interposici\u00f3n de la presente acci\u00f3n de tutela (f. \u00a0 32 ib.). \u00a0 \u00a0<\/p>\n<p>2. C\u00e9dula de ciudadan\u00eda 19.129.186 \u00a0 de Bogot\u00e1, correspondiente al referido doctor, en la que consta que naci\u00f3 en \u00a0 mayo 30 de 1951 (f. 34 ib.). \u00a0 \u00a0<\/p>\n<p>3. \u00a0 Diploma de doctor en Medicina y Cirug\u00eda, otorgado al actor por la Pontificia Universidad Javeriana, en julio 9 de 1976 \u00a0 (f. 35 ib.). \u00a0 \u00a0<\/p>\n<p>4. \u00a0 Certificaci\u00f3n expedida por el Jefe de la Unidad en Gastroenterolog\u00eda del \u00a0 Hospital Universitario de San Ignacio en diciembre 31 de 1991, en el que consta \u00a0 que el actor \u00a0\u201casisti\u00f3 y particip\u00f3 de todas las actividades de la Unidad de \u00a0 Gastroenterolog\u00eda del Hospital Universitario de San Ignacio, durante el per\u00edodo \u00a0 comprendido entre los meses de enero a diciembre de 1991\u2026 Durante \u00a0 su entrenamiento recibi\u00f3 instrucci\u00f3n de Endoscopia Digestiva, con pr\u00e1cticas \u00a0 supervisadas de 385 Endoscopias\u201d (f. 38 ib.). \u00a0 \u00a0<\/p>\n<p>5. \u00a0 Certificaci\u00f3n expedida por el mismo funcionario en diciembre 11 de 1997, donde \u00a0 consta que el accionante \u00a0\u201crealiz\u00f3 un entrenamiento de Endoscopia Digestiva en la Unidad que \u00a0 actualmente dirijo, durante el per\u00edodo comprendido entre los meses de enero a \u00a0 diciembre de 1991. Posteriormente ha asistido a per\u00edodos de actualizaci\u00f3n \u00a0 durante cinco semanas en el a\u00f1o de 1996 y ocho semanas en el presente a\u00f1o\u201d \u00a0 (f. 39 ib.). \u00a0 \u00a0<\/p>\n<p>6. \u00a0 Comunicaci\u00f3n dirigida al actor por la representante de la Direcci\u00f3n General de \u00a0 Calidad de Servicios del Ministerio de Protecci\u00f3n Social en julio 29 de 2008, \u00a0 donde le informa que para realizar endoscopias digestivas, es indispensable \u00a0 cumplir los requisitos de la Resoluci\u00f3n 1043 de 2006; sin embargo, en su caso \u00a0 procede aplicar el par\u00e1grafo 2\u00b0 del art\u00edculo 18 de la Ley 1164 de 2007, pues al \u00a0 momento de su expedici\u00f3n el servicio donde ejerc\u00eda estaba habilitado. Por tanto, \u00a0 \u201cprocede otorgar a este profesional el per\u00edodo de transici\u00f3n definido en esta \u00a0 \u00faltima norma. Superado el per\u00edodo de transici\u00f3n, el profesional deber\u00e1 acreditar \u00a0 el t\u00edtulo correspondiente\u201d (fs. 74 a 76 ib.). \u00a0 \u00a0<\/p>\n<p>7. Contrato de prestaci\u00f3n de \u00a0 servicios suscrito entre el Departamento de Boyac\u00e1 y el actor en noviembre 5 de \u00a0 2010, para desarrollar acciones como gerente de la pol\u00edtica p\u00fablica \u201cEl Nuevo \u00a0 Ciudadano Boyacense\u201d, con una duraci\u00f3n de 12 meses y 26 d\u00edas, por valor de \u00a0 $84\u2019000.000 (fs. 80 a 83 ib.). \u00a0 \u00a0<\/p>\n<p>8. \u00a0 Certificaci\u00f3n expedida por el gerente del Centro de Ayudas Diagn\u00f3sticas en enero \u00a0 21 de 2013, donde consta que el accionante prest\u00f3 sus servicios en el \u00e1rea de \u00a0 endoscopias de v\u00edas digestivas entre 1991 y 1997, como galeno adscrito en trece \u00a0 entidades m\u00e9dicas, realizando un total de 5.188 endoscopias de v\u00edas digestivas \u00a0 altas y 991 de v\u00edas digestivas bajas (f. 90 ib.). \u00a0 \u00a0<\/p>\n<p>9. \u00a0 Certificaci\u00f3n del gerente de la Cl\u00ednica Especializada de Los Andes S. A. en \u00a0 junio 19 de 2012, donde informa que el actor prest\u00f3 sus servicios en el \u00e1rea de \u00a0 endoscopias de v\u00edas digestivas entre 1998 y agosto 30 de 2010, como galeno \u00a0 adscrito en 70 entidades m\u00e9dicas relacionadas (fs. 91 y 92 ib.). \u00a0 \u00a0<\/p>\n<p>10. \u00a0 Comunicaci\u00f3n dirigida por el actor al Secretario de Salud de Boyac\u00e1 de octubre 8 \u00a0 de 2012, donde solicita \u201ccertificaci\u00f3n\u2026 para efectos de prestar el servicio \u00a0 de Endoscopia Digestiva alta y baja, como profesional independiente, a las \u00a0 diferentes Instituciones Prestadoras IPS y EPS promotoras que deseen contratar \u00a0 mis servicios en sus propias instalaciones\u201d (f. 94 ib.). \u00a0 \u00a0<\/p>\n<p>11. Oficio dirigido por el \u00a0 Secretario de Salud de Boyac\u00e1 al demandante en octubre 22 de 2012, donde le \u00a0 informa que al no cumplir los requisitos legales, \u201cno es procedente expedir \u00a0 certificaci\u00f3n alguna a su nombre para efectos de prestar el servicio de \u00a0 endoscopia digestiva alta y baja\u201d (f. 95 ib.). \u00a0 \u00a0<\/p>\n<p>12. Registro civil de nacimiento \u00a0 de la hija del actor, Luisa Mar\u00eda Rivero Bernal, donde consta que naci\u00f3 en julio \u00a0 14 de 1989 (f. 96 ib.). \u00a0 \u00a0<\/p>\n<p>13. Orden de matr\u00edcula de Luisa \u00a0 Mar\u00eda Rivero Bernal, expedida por la Universidad La Sabana en diciembre 13 de \u00a0 2012, para el programa de pedagog\u00eda infantil, por valor de $4\u2019042.500 (f. 98 \u00a0 ib.). \u00a0 \u00a0<\/p>\n<p>14. Declaraci\u00f3n extrajuicio \u00a0 rendida por el accionante ante el Notario 52 del C\u00edrculo de Bogot\u00e1 en enero 23 \u00a0 de 2013, donde relata que \u201cla lesi\u00f3n causada por la Resoluci\u00f3n 1043 de 2006 y \u00a0 la Ley 1164 de 2007 es enorme e indescriptible. He tenido que ver afectada mi \u00a0 situaci\u00f3n familiar, profesional, laboral, econ\u00f3mica, social y de salud sin tener \u00a0 la posibilidad de reincorporarme laboralmente, as\u00ed como ver la angustia de mi \u00a0 esposa e hijos. Pertenezco al ciclo de vida del adulto mayor para el que se \u00a0 exige protecci\u00f3n pero no ha sido as\u00ed en mi caso. He tenido que recurrir a \u00a0 pr\u00e9stamos e ir acabando con el escaso peculio obtenido honestamente durante una \u00a0 vida larga laboral para tratar de subsistir\u2026 tengo bajo mi responsabilidad a mi \u00a0 hija Lisa Mar\u00eda Rivero a quien a\u00fan le faltan 3 a\u00f1os de pregrado, sin contar lo \u00a0 de las pr\u00e1cticas no remuneradas y su sostenimiento en la ciudad de Bogot\u00e1. \u00a0 Tambi\u00e9n tengo bajo mi sustento a mi esposa, Clara Bernal quien tampoco cuenta \u00a0 con un trabajo y el de mi sobrino, quien lamentablemente por esta situaci\u00f3n no \u00a0 pudo continuar estudiando\u2026\u201d (fs. 103 y 104 ib.). \u00a0 \u00a0<\/p>\n<p>15. Resoluci\u00f3n del entonces \u00a0 Ministerio de la Protecci\u00f3n Social 1043 de abril 3 de 2006 y anexo t\u00e9cnico 1, \u00a0 \u201cpor la cual se establecen las condiciones que deben cumplir los prestadores de \u00a0 servicios de salud para habilitar sus servicios e implementar el componente de \u00a0 auditoria para el mejoramiento de la calidad de la atenci\u00f3n\u201d (fs. 108 y 128 \u00a0 ib.). \u00a0 \u00a0<\/p>\n<p>16. Formato de inscripciones 2012 \u00a0 con el Hospital Universitario San Ignacio de la Pontificia Universidad \u00a0 Javeriana, donde consta que la especialidad en Gastroenterolog\u00eda y Endoscopia \u00a0 Digestiva tiene una duraci\u00f3n de 2 a\u00f1os,y se exige como requisito una \u00a0 especialidad en medicina interna, cuyo costo por semestre es de $7\u00b4140.000. Por \u00a0 su parte la especialidad en medicina interna dura 3 a\u00f1os y su valor asciende a \u00a0 $11\u00b4458.000 (f. 129 ib.). \u00a0 \u00a0<\/p>\n<p>17. \u00a0 Certificados y constancias de asistencia a cursos y congresos, expedidos por las \u00a0 respectivas instituciones organizadoras al doctor Germ\u00e1n Rivero Romero: (i) \u00a0 Simposio de Gastroenterolog\u00eda y Reumatolog\u00eda, organizado por Asmedas Seccional \u00a0 Boyac\u00e1 en octubre 3 de 1991; (ii) Convenci\u00f3n Nacional de Gastroenterolog\u00eda, \u00a0 Endoscopia Digestiva y Coloproctolog\u00eda, organizada por las Sociedades \u00a0 Colombianas de las referidas especialidades del 9 al 11 de octubre de 1991 en \u00a0 Bogot\u00e1; (iii) Primer Seminario Taller Nacional sobre C\u00e1ncer de Est\u00f3mago, \u00a0 organizado por la Asociaci\u00f3n Interamericana de Gastroenterolog\u00eda y otras \u00a0 entidades del 2 al 4 de abril de 1992 en Huila; (iv) Curso en Servicio de \u00a0 Gastroenterolog\u00eda, organizado por la Universidad Nacional y Paris VIII del 18 al \u00a0 20 de mayo de 1992, en Bogot\u00e1; (v) Curso de Actualizaci\u00f3n en Gastroenterolog\u00eda, \u00a0 organizado por la Sociedad de Gastroenterolog\u00eda y otras entidades en septiembre \u00a0 24 de 1993 en Paipa; (vi) Convenci\u00f3n Nacional de Gastroenterolog\u00eda, Endoscopia \u00a0 Digestiva, Coloproctolog\u00eda y Hepatolog\u00eda, organizada por las Sociedades \u00a0 Colombianas de las referidas especialidades del 20 al 23 de octubre de 1993 en \u00a0 Bogot\u00e1; (vii) Simposio de Actualizaci\u00f3n en Gastroenterolog\u00eda, realizado por la \u00a0 Sociedad Colombiana de Gastroenterolog\u00eda en abril 22 de 1994 en Bogot\u00e1; (viii) \u00a0 Curso Internacional de Endoscopia Digestiva, realizado por la Asociaci\u00f3n \u00a0 Colombiana de Endoscopia Digestiva del 8 al 10 de febrero de 1996 en Bogot\u00e1; \u00a0 (ix) Congreso Colombiano de Enfermedades Digestivas, organizado por la Sociedad \u00a0 Colombiana de Gastroenterolog\u00eda y otras entidades del 14 al 17 de octubre de \u00a0 1999 en Bogot\u00e1; (x) IV Curso Internacional de Endoscopia Digestiva, organizado \u00a0 por la Asociaci\u00f3n Colombiana de Endoscopia Digestiva del 20 al 22 de junio de \u00a0 2002 en Cartagena; y (xi) Congreso Colombiano de Enfermedades Digestivas, \u00a0 realizado por la Asociaci\u00f3n Colombiana de Asociaciones del Aparato Digestivo del \u00a0 10 al 12 de octubre de 2003 en Paipa (fs. 40 a 50 ib.). \u00a0 \u00a0<\/p>\n<p>18. \u00a0 Certificaci\u00f3n expedida por el actor en enero 22 de 2013, donde informa que ha \u00a0 \u201cpracticado aproximadamente 17.777 procedimientos de endoscopia digestiva Alta y \u00a0 Baja. Adem\u00e1s certific\u00f3 que registr\u00f3 en un CD-ROOM la pr\u00e1ctica de 10.998 \u00a0 procedimientos, aproximadamente\u201d (f. 180 ib.). \u00a0 \u00a0<\/p>\n<p>C. Respuesta \u00a0 de la Secretar\u00eda de Salud de Boyac\u00e1. \u00a0 \u00a0<\/p>\n<p>En febrero 8 de 2013, el \u00a0 Secretario de Salud de Boyac\u00e1 se opuso a las pretensiones de la acci\u00f3n de \u00a0 tutela, manifestando que \u201clas disposiciones que rigen la materia determinan \u00a0 que es necesario que se cuente con los requisitos de estudio referidos en dichas \u00a0 normas para el ejercicio de la profesi\u00f3n y de las actividades que reclama el \u00a0 doctor Riveros por lo que al no cumplir con las mismas no es procedente ni \u00a0 f\u00e1ctica ni jur\u00eddicamente a la Secretar\u00eda de Salud de Boyac\u00e1 realizar inscripci\u00f3n \u00a0 de servicios que no se encuentren acorde con lo regulado\u201d (f. 275 ib.). \u00a0 \u00a0<\/p>\n<p>D. Respuesta \u00a0 del Ministerio de Salud y Protecci\u00f3n Social. \u00a0 \u00a0<\/p>\n<p>En febrero 12 de 2013, el Director \u00a0 Jur\u00eddico del Ministerio de Salud y Protecci\u00f3n Social solicit\u00f3 declarar \u00a0 improcedente el amparo, por cuanto \u201cuna vez revisados los documentos y \u00a0 soportes allegados, se observa que se anex\u00f3 el t\u00edtulo otorgado en pregrado y no \u00a0 hay t\u00edtulo de especialista\u201d, el cual se requiere acreditar para realizar \u00a0 endoscopias digestivas. Advirti\u00f3 que la relaci\u00f3n de asistencia en salud genera \u00a0 una obligaci\u00f3n de medio, basada en la competencia, que asigna a los \u00a0 profesionales de la salud la responsabilidad permanente de la autorregulaci\u00f3n, \u00a0 en el marco de un ejercicio responsable, \u00e9tico y competente (f. 283 ib.). \u00a0 \u00a0<\/p>\n<p>E. Sentencia de primera \u00a0 instancia. \u00a0 \u00a0<\/p>\n<p>En fallo de febrero 21 de 2013, la \u00a0 Sala de Decisi\u00f3n Segunda del Tribunal Administrativo de Boyac\u00e1 declar\u00f3 \u00a0 improcedente la acci\u00f3n, indicando que \u201cno se observa vulneraci\u00f3n al m\u00ednimo \u00a0 vital\u2026 pues el Ministerio de Protecci\u00f3n Social mediante oficio 275722 del 16 de \u00a0 septiembre de 2008\u2026 habilit\u00f3 al accionante para la pr\u00e1ctica de los \u00a0 procedimientos de endoscopia digestiva, para el per\u00edodo de transici\u00f3n \u00a0 establecido en el par\u00e1grafo 2\u00b0 del art\u00edculo 18 de la Ley 1164 de 2007 (3 a\u00f1os), \u00a0 indic\u00e1ndole adicionalmente que superado ese t\u00e9rmino (3 de octubre de 2010) \u00a0 deber\u00eda acreditar el t\u00edtulo correspondiente en dicha especialidad, pues no basta \u00a0 la realizaci\u00f3n de simposios, jornadas de actualizaci\u00f3n, talleres o cursos y la \u00a0 pr\u00e1ctica en distintas entidades del sector salud para suplir el requisito \u00a0 previsto en la ley\u201d (f. 305 ib.). \u00a0 \u00a0<\/p>\n<p>Precis\u00f3 que el doctor Germ\u00e1n \u00a0 Rivero Romero conoc\u00eda el requisito que deb\u00eda cumplir y acreditar para la \u00a0 pr\u00e1ctica de endoscopias digestivas, pero se abstuvo de cursar el programa \u00a0 acad\u00e9mico que exige la norma para habilitarlo en dichos procedimientos. Adem\u00e1s, \u00a0\u201cel accionante ha venido realizando funciones distintas a la pr\u00e1ctica de \u00a0 endoscopias, al desempe\u00f1arse como gerente de la pol\u00edtica p\u00fablica departamental, \u00a0 por lo que no se puede concluir, entonces, que s\u00f3lo percibe ingresos econ\u00f3micos \u00a0 por dicha actividad\u201d (f. 305 ib.). \u00a0 \u00a0<\/p>\n<p>Explic\u00f3 que el actor puede acudir \u00a0 a la jurisdicci\u00f3n contencioso administrativa para debatir la legalidad del \u00a0 oficio expedido por la Secretaria de Salud de Boyac\u00e1 en octubre 22 de 2012, que \u00a0 le neg\u00f3 la autorizaci\u00f3n para realizar endoscop\u00edas digestivas, teniendo adem\u00e1s en \u00a0 cuenta que en dicho proceso es posible pedir la suspensi\u00f3n provisional del acto \u00a0 acusado (f. 301 ib.). \u00a0 \u00a0<\/p>\n<p>F. Impugnaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Mediante escrito de febrero 26 de \u00a0 2013, el apoderado del actor impugn\u00f3 el fallo antes referido, reiterando lo \u00a0 expresado en la demanda de tutela y adicionando que la decisi\u00f3n en un proceso \u00a0 contencioso administrativo se producir\u00eda a\u00f1os despu\u00e9s \u201cde la correspondiente \u00a0 demanda, lo cual perpetuar\u00eda en el tiempo la grave situaci\u00f3n de indefensi\u00f3n \u00a0 econ\u00f3mica de mi mandante\u2026 En ese mismo sentido, t\u00e9ngase presente que mi mandante \u00a0 no percibe actualmente un ingreso fijo, ni mucho menos una pensi\u00f3n, pues su \u00a0 propia subsistencia en el mayor de los casos depende de la solidaridad y apoyo \u00a0 econ\u00f3mico proveniente de dos de sus hijos mayores que trabajan, por lo tanto, no \u00a0 cuenta con los recursos econ\u00f3micos que le permitan afrontar un proceso \u00a0 contencioso de esa naturaleza\u201d (fs. 312 y 324 ib.). \u00a0 \u00a0<\/p>\n<p>G. Sentencia de segunda \u00a0 instancia. \u00a0 \u00a0<\/p>\n<p>En marzo 22 de 2013, la Secci\u00f3n \u00a0 Cuarta del Consejo de Estado confirm\u00f3 el fallo impugnado, reiterando que el \u00a0 actor cuenta con otro medio de defensa judicial y no hallando configurado un \u00a0 perjuicio irremediable, pues \u201cen la actualidad cuenta con un contrato de \u00a0 prestaci\u00f3n de servicios suscrito con el departamento de Boyac\u00e1 que le permite \u00a0 garantizar un ingreso para su congrua subsistencia, adem\u00e1s que es un profesional \u00a0 de la medicina que puede ejercer su oficio de manera independiente\u201d \u00a0(f. 348 ib.). \u00a0 \u00a0<\/p>\n<p>H. Actuaci\u00f3n dentro del tr\u00e1mite de revisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>1. Mediante \u00a0 auto de noviembre 22 de 2013, esta corporaci\u00f3n dispuso oficiar al Ministerio de Educaci\u00f3n Nacional, para que adem\u00e1s de lo \u00a0 que deseara expresar frente a los hechos objeto de esta acci\u00f3n, informara qu\u00e9 \u00a0 instituciones universitarias en Bogot\u00e1 y Tunja ofrecen los programas de \u00a0 especializaci\u00f3n en gastroenterolog\u00eda, gastroenterolog\u00eda pedi\u00e1trica, pediatr\u00eda, \u00a0 coloproctolog\u00eda y cirug\u00eda pedi\u00e1trica, cu\u00e1les son los requisitos para ser \u00a0 admitido y los costos. \u00a0 \u00a0<\/p>\n<p>Tambi\u00e9n se requiri\u00f3 a la \u00a0 Asociaci\u00f3n Colombiana de Endoscopia Digestiva, ACED, para que rindiera un \u00a0 concepto sobre los hechos del caso, adem\u00e1s de lo que deseara expresar, solicitar \u00a0 o controvertir. \u00a0 \u00a0<\/p>\n<p>2. En escrito de noviembre 28 \u00a0 de 2013, la Junta Directiva de la Asociaci\u00f3n Colombiana de Endoscopia Digestiva \u00a0 inform\u00f3 (f. 65 ib.): \u00a0 \u00a0<\/p>\n<p>\u201c1. La realizaci\u00f3n de endoscopia digestiva requiere conocimientos \u00a0 pr\u00e1cticos y te\u00f3ricos fundamentados en ciencias cl\u00ednicas y b\u00e1sicas de la \u00a0 medicina. \u00a0 \u00a0<\/p>\n<p>2. La endoscopia digestiva ha evolucionado de una manera muy \u00a0 importante. \u00a0 \u00a0<\/p>\n<p>3. Su aprendizaje debe ser parte de un programa acad\u00e9mico de educaci\u00f3n \u00a0 universitaria NO menor de 2 a\u00f1os adicionales en un programa formal, de \u00a0 subespecializaci\u00f3n autorizado, avalado y auditado por el Ministerio de \u00a0 Educaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>4 Dicho programa de subespecializacion debe ser realizado por m\u00e9dicos, \u00a0 con especializaci\u00f3n y t\u00edtulo en medicina interna o cirug\u00eda general. \u00a0 \u00a0<\/p>\n<p>5. Todo esto con el \u00fanico fin de mejorar la calidad y atenci\u00f3n con la \u00a0 seguridad necesaria en todos y cada uno de nuestros pacientes en el pa\u00eds.\u201d \u00a0 \u00a0<\/p>\n<p>Anex\u00f3 un trabajo realizado por la propia Asociaci\u00f3n \u00a0 Colombiana de Endoscopia Digestiva, denominado \u201cPrimer consenso colombiano \u00a0 sobre la pr\u00e1ctica de endoscopia digestiva \u2018Acuerdo en lo fundamental\u2019 (Primera \u00a0 parte: Aspectos formativos)\u201d, publicado en la Revista Colombiana de \u00a0 Gastroenterolog\u00eda de marzo 27 de 2012[1], \u00a0 sobre la necesidad de entrenamiento adecuado en la t\u00e9cnica de endoscopia \u00a0 digestiva, \u201ctan valiosa como dif\u00edcil de aprender\u201d, para cuya elaboraci\u00f3n \u00a0\u201cse reunieron los jefes de los programas universitarios de gastroenterolog\u00eda y \u00a0 endoscopia digestiva, de cirug\u00eda gastrointestinal, presidentes y ex presidentes \u00a0 de las Asociaciones del Aparato Digestivo, Gastroenterolog\u00eda, y Endoscopia \u00a0 Digestiva, representantes de las Asociaciones Colombiana de Medicina Interna y \u00a0 Cirug\u00eda, as\u00ed como los principales l\u00edderes de opini\u00f3n de Endoscopia Digestiva y \u00a0 Gastroenterolog\u00eda reconocidos acad\u00e9micamente\u201d. \u00a0 \u00a0<\/p>\n<p>En la \u00a0 publicaci\u00f3n se expres\u00f3 que el escenario de la pr\u00e1ctica en gastroenterol\u00f3gica y \u00a0 endosc\u00f3pica es muy complejo en Colombia, toda vez que est\u00e1 determinado por \u00a0 diferentes concepciones, normatividades e intereses (fs. 66 a 72 ib.), como en \u00a0 extenso se transcribe a continuaci\u00f3n: \u00a0 \u00a0<\/p>\n<p>\u201cLa Resoluci\u00f3n 1043 de 2006 (por la cual se establecen las condiciones \u00a0 que deben cumplir los prestadores de servicios de salud para habilitar sus \u00a0 servicios), determina en su Anexo T\u00e9cnico N\u00b0 1, numeral 1\u00ba Recurso Humano, que \u00a0 la gastroenterolog\u00eda y endoscopia de v\u00edas digestivas puede ser ejercida por \u00a0 \u2018m\u00e9dicos especializados en gastroenterolog\u00eda, gastroenterolog\u00eda pedi\u00e1trica, \u00a0 coloproctolog\u00eda, medicina interna con subespecialidad en gastroenterolog\u00eda; y \u00a0 pediatr\u00eda, cirug\u00eda pedi\u00e1trica, cirug\u00eda general o medicina interna que en su \u00a0 formaci\u00f3n demuestren haber recibido entrenamiento de un a\u00f1o en endoscopia de \u00a0 v\u00edas digestivas certificado por una instituci\u00f3n de educaci\u00f3n superior reconocida \u00a0 por el Estado\u2019. \u00a0 \u00a0<\/p>\n<p>La Ley 1164 de 2007 (por la cual se dictan disposiciones en \u00a0 materia de Talento Humano en Salud) modificada posteriormente con la Ley 1438 de \u00a0 2011, estipula \u2018las caracter\u00edsticas acerca de la formaci\u00f3n, ejercicio y gesti\u00f3n \u00a0 de las profesiones del \u00e1rea de la salud\u2019 en coherencia con la poblaci\u00f3n \u00a0 colombiana y las caracter\u00edsticas y objetivos del sistema general de seguridad \u00a0 social en salud definidos en la Ley 100 de 1993. \u00a0 \u00a0<\/p>\n<p>Las mencionadas leyes complejizan el escenario cuando determinan las \u00a0 relaciones que debe tener el talento humano en salud desde su ejercicio (estas \u00a0 leyes son expedidas desde el Ministerio de Protecci\u00f3n Social), con el escenario \u00a0 del Ministerio de Educaci\u00f3n cuyas directrices generales, que tocan la formaci\u00f3n \u00a0 de postgrado, est\u00e1n estipuladas en la Ley 30 de 1992 y la Ley 115 de 1994. \u00a0 \u00a0<\/p>\n<p>Como se puede apreciar, la definici\u00f3n de las caracter\u00edsticas formativas \u00a0 para la practica de la gastroenterolog\u00eda y endoscopia digestiva se dictaron \u00a0 desde un escenario diferente al educativo y con antelaci\u00f3n a la b\u00fasqueda de las \u00a0 relaciones arm\u00f3nicas y comprensivas que han de tener los espacios laborales y \u00a0 pedag\u00f3gicos, especialmente en un campo tan sensible de la poblaci\u00f3n colombiana \u00a0 como es el de la salud digestiva. \u00a0 \u00a0<\/p>\n<p>Las evidentes incongruencias generadas por esta amplia normatividad han \u00a0 propiciado m\u00faltiples tensiones entre los diferentes especialistas; las \u00a0 asociaciones cient\u00edficas; entre estas y los ministerios mencionados; los m\u00e9dicos \u00a0 que han ido a recibir alg\u00fan tipo de formaci\u00f3n (usualmente endosc\u00f3pica) en el \u00a0 exterior y que a su retorno buscan la convalidaci\u00f3n de su t\u00edtulo profesional \u00a0 (ICFES); entre quienes ejercen la gastroenterolog\u00eda (cl\u00ednica y\/o quir\u00fargica) \u00a0 luego de ser especialistas y realizar una subespecialidad y aquellos que la \u00a0 ejercen luego de ser especialistas y recibir capacitaci\u00f3n de un a\u00f1o. \u00a0 \u00a0<\/p>\n<p>\u2026\u00a0 \u00a0\u2026\u00a0\u00a0 \u2026 \u00a0 \u00a0<\/p>\n<p>Expresada la complejidad (y hasta cierto punto la desorganizaci\u00f3n) \u00a0 legal, acad\u00e9mica y laboral en la que circula la endoscopia digestiva, el estudio \u00a0 ha hecho evidente que, a pesar de que en lo pedag\u00f3gico los programas de \u00a0 formaci\u00f3n nacionales para especializaci\u00f3n en gastroenterolog\u00eda han definido un \u00a0 perfil del egresado encaminado a lograr \u2018especialista con liderazgo, con \u00a0 habilidades para transmitir conocimiento y desarrollar programas de \u00a0 investigaci\u00f3n\u2019, con un amplio conocimiento en habilidades del sistema digestivo \u00a0 \u2018para entender, aprender y aplicar los diversos avances tecnol\u00f3gicos en \u00a0 endoscopia gastrointestinal\u2019, la realidad muestra que no se est\u00e1 cumpliendo con \u00a0 la obtenci\u00f3n plena de este perfil en los m\u00e9dicos que ejercen la endoscopia \u00a0 digestiva. Todos los programas en el pa\u00eds tienen como par\u00e1metro para su ingreso \u00a0 el ser especialista en Medicina Interna o Cirug\u00eda General. Por otra parte, hasta \u00a0 el 2006 el ejercicio de la endoscopia digestiva estaba autorizado solo para \u00a0 egresados de estos programas, entendi\u00e9ndose a la endoscopia digestiva como \u00a0 elemento importante (m\u00e1s no central ni definitivo) del ejercicio m\u00e9dico \u00a0 relacionado con las enfermedades digestivas. \u00a0 \u00a0<\/p>\n<p>El consenso actual logr\u00f3 llegar a acuerdos encaminados a mostrar la \u00a0 impertinencia de aceptar tiempos de formaci\u00f3n en endoscopia digestiva de solo un \u00a0 a\u00f1o y luego de una especializaci\u00f3n general; y mostrar, la pertinencia (dados los \u00a0 avances cient\u00edficos, tecnol\u00f3gicos y las implicaciones sociales y \u00e9ticas) de \u00a0 exigir, para el ejercicio de la endoscopia b\u00e1sica un tiempo de formaci\u00f3n no \u00a0 menor a 2 a\u00f1os; y para la endoscopia avanzada, un tiempo de formaci\u00f3n total \u00a0 entre 3 y 4 a\u00f1os. En ambas circunstancias, siempre como parte de un programa de \u00a0 subespecialidad en gastroenterolog\u00eda, sea cl\u00ednica (gastroenterolog\u00eda, \u00a0 gastroenterolog\u00eda pedi\u00e1trica) o quir\u00fargica (cirug\u00eda gastrointestinal, \u00a0 coloproctolog\u00eda, cirug\u00eda pedi\u00e1trica), acogi\u00e9ndose a est\u00e1ndares internacionales. \u00a0 \u00a0<\/p>\n<p>Estas caracter\u00edsticas formativas se apoyan en la importancia de \u00a0 acercarse al desarrollo de la capacidad cognitiva acerca de las patolog\u00edas \u00a0 digestivas as\u00ed como a la habilidad t\u00e9cnica en los procedimientos al igual que en \u00a0 la capacidad interpretativa y propositiva de los estudios para hacer una \u00a0 adecuada propuesta de tratamiento, recuperaci\u00f3n o rehabilitaci\u00f3n. Igualmente se \u00a0 lleg\u00f3 a un consenso positivo sobre la importancia de introducir expl\u00edcitamente \u00a0 actividades formativas relacionadas con la \u00e9tica y los valores, administraci\u00f3n y \u00a0 la gesti\u00f3n. El consenso no ha desconocido la normatividad legal vigente en \u00a0 Colombia a 2012, donde se permite que los Cirujanos Generales o Internistas con \u00a0 un a\u00f1o de entrenamiento (avalado por una instituci\u00f3n universitaria) puedan \u00a0 realizar endoscopia digestiva. Tampoco desconoci\u00f3 la motivaci\u00f3n gubernamental \u00a0 para haber autorizado este tipo de pr\u00e1ctica m\u00e9dica, basado en criterios de \u00a0 universalidad, equidad e igualdad que son definidos como principios del Sistema \u00a0 General de Seguridad Social en Salud, por un aparente o real d\u00e9ficit de \u00a0 especialistas en esta \u00e1rea de la Salud (art. 153 de la Ley 100 de 1993 y \u00a0 articulo 3 de la Ley 1438 de 2011). \u00a0 \u00a0<\/p>\n<p>El consenso ha puesto, en contraposici\u00f3n a estos postulados, otro \u00a0 principio del mismo sistema y de las leyes mencionadas: nos referimos al \u00a0 principio de calidad. Han sido m\u00faltiples las manifestaciones por la cuales se ha \u00a0 llegado a un consenso para no recomendar que se siga permitiendo la pr\u00e1ctica de \u00a0 la endoscopia digestiva, ni siquiera la b\u00e1sica diagn\u00f3stica, con tan poco tiempo \u00a0 de preparaci\u00f3n. Pues no es esta una pr\u00e1ctica \u00e9tica ni moral, pues la supuesta \u00a0 equidad e igualdad no se les puede asegurar a los pacientes si el profesional \u00a0 que lo est\u00e1 examinando no cuenta con el adecuado y suficiente nivel de \u00a0 preparaci\u00f3n, de acuerdo a la opini\u00f3n de los mayores expertos de la \u00a0 gastroenterolog\u00eda del pa\u00eds. \u00a0 \u00a0<\/p>\n<p>No es el criterio central para avalar la adecuada formaci\u00f3n en \u00a0 endoscopia digestiva el certificar un n\u00famero determinado de procedimientos. Son \u00a0 las caracter\u00edsticas acad\u00e9micas, tecnol\u00f3gicas supervisadas con seguimiento, \u00a0 investigadas, las que vuelven a un determinado n\u00famero de procedimientos \u00a0 efectivamente en una evidencia de adecuada formaci\u00f3n. Evidencia formativa que s\u00ed \u00a0 se constituye en un instrumento que genere justicia social. \u00a0 \u00a0<\/p>\n<p>Estas consideraciones relativas al tipo de formaci\u00f3n previa y a los \u00a0 tiempos m\u00ednimos de formaci\u00f3n no surgieron de forma prejuiciosa; se observaron \u00a0 estructurados desde reflexiones en profesores y profesionales, la mayor\u00eda de \u00a0 ellos con m\u00e1s de 20 a\u00f1os de experiencia docente y laboral, para quienes el \u00a0 centro de la discusi\u00f3n esta en la forma como se entiende lo que es la endoscopia \u00a0 digestiva. El consenso rechaz\u00f3 con amplitud el ver a la endoscopia digestiva \u00a0 como una especialidad independiente de las especialidades relacionadas con \u00a0 enfermedades digestivas. Igualmente, no la aprecian como una simple t\u00e9cnica \u00a0 aplicable indiscriminadamente por otras especialidades no centradas en \u00a0 enfermedades digestivas. Por el contrario la endoscopia digestiva se aprecia \u00a0 como parte de toda una formaci\u00f3n integral dentro de las especialidades \u00a0 gastroenterolog\u00edas mencionadas previamente. \u00a0 \u00a0<\/p>\n<p>En ese sentido, el consenso fue cuidadoso en no ceder la \u00a0 responsabilidad de la formaci\u00f3n endosc\u00f3pica a pr\u00e1cticas centradas en t\u00e9cnicas, \u00a0 por muy especializadas que ellas sean; ni los recursos econ\u00f3micos o tecnol\u00f3gicos \u00a0 pueden reemplazar ni desplazar la formaci\u00f3n integral que debe aportar el docente \u00a0 de gastroenterolog\u00eda y endoscopia digestiva; docente que debe prepararse para \u00a0 ser tal, apoy\u00e1ndose en los diferentes programas de cualificaci\u00f3n pedag\u00f3gica \u00a0 existentes en las universidades o en algunas asociaciones cient\u00edficas mundiales. \u00a0 \u00a0<\/p>\n<p>Cuando las discusiones, en instancias internacionales como Asociaci\u00f3n \u00a0 Americana de Endoscopia Gastrointestinal (ASGE) y Sociedad Interamericana de \u00a0 Endoscopia Digestiva (SIED) se diseccionan desde curr\u00edculos centrales (Core \u00a0 Curriculum) y se centran en aspectos formativos y de calidad (comprensi\u00f3n \u00a0 hol\u00edstica de la endoscopia; cumplimiento de bioseguridad; mejora en \u00a0 interpretaci\u00f3n de hallazgos endosc\u00f3picos; identificaci\u00f3n de factores de riesgo; \u00a0 limitaciones de los procedimientos; o mediciones de calidad), \u00a0en nuestro \u00a0 escenario debemos a\u00fan resolver retos que no tienen que ver estrictamente con \u00a0 procesos formativos o asistenciales o investigativos (por ejemplo, el tipo de \u00a0 contrataci\u00f3n laboral de los intermediarios del sistema o la definici\u00f3n de pisos \u00a0 tarifarios). \u00a0 \u00a0<\/p>\n<p>Pero es responsabilidad de todos los actores entrar a solucionar las \u00a0 divergencias, toda vez que la dimensi\u00f3n formativa en endoscopia digestiva \u00a0 acarrea, como toda pr\u00e1ctica m\u00e9dica, un deber \u00e9tico y moral que debe ir m\u00e1s all\u00e1 \u00a0 de cualquier inter\u00e9s que lo aleje de ejercer una acci\u00f3n medica que asegure el \u00a0 bienestar integral del paciente.\u201d \u00a0 \u00a0<\/p>\n<p>3. En escrito de noviembre 29 \u00a0 de 2013, un asesor jur\u00eddico del Ministerio de Educaci\u00f3n indic\u00f3 que luego de \u00a0 consultar los programas de especializaci\u00f3n en el Sistema Nacional de Informaci\u00f3n \u00a0 de la Educaci\u00f3n Superior, se verific\u00f3 que ninguno de ellos es ofrecido en Tunja, \u00a0 y que en Bogot\u00e1 se brindan por las siguientes instituciones de educaci\u00f3n \u00a0 superior (fs. 73 y 74 ib.): \u00a0 \u00a0<\/p>\n<p>\u201cGastroenterolog\u00eda: \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Fundaci\u00f3n Universitaria de Ciencias de la Salud \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Pontificia Universidad Javeriana \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Colegio Mayor de Nuestra Se\u00f1ora del Rosario \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Fundaci\u00f3n Universitaria Sanitas \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Universidad Militar Nueva Granada \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Universidad Nacional de Colombia \u00a0 \u00a0<\/p>\n<p>Gastroenterolog\u00eda Pedi\u00e1trica: \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Fundaci\u00f3n Universitaria de Ciencias de la Salud \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Pontificia Universidad Javeriana \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Colegio Mayor de Nuestra Se\u00f1ora del Rosario \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Fundaci\u00f3n Universitaria Sanitas \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Universidad Militar Nueva Granada \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Universidad del Bosque \u00a0 \u00a0<\/p>\n<p>Coloproctolog\u00eda: \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Universidad Militar Nueva Granada \u00a0 \u00a0<\/p>\n<p>Cirug\u00eda Pedi\u00e1trica: \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Universidad Militar Nueva Granada \u00a0 \u00a0<\/p>\n<p>\u00b7 \u00a0 Universidad Nacional de Colombia\u201d \u00a0 \u00a0<\/p>\n<p>Con respecto a los requisitos para ingresar a los \u00a0 referidos programas acad\u00e9micos, anot\u00f3 que suponen la culminaci\u00f3n del ciclo de \u00a0 pregrado; en relaci\u00f3n a los costos, sostuvo que son establecidos por cada \u00a0 instituci\u00f3n de educaci\u00f3n superior. \u00a0 \u00a0<\/p>\n<p>4. La complejidad del caso condujo a esta Sala de Revisi\u00f3n, por \u00a0 medio de auto de diciembre 2 de 2013, a suspender los t\u00e9rminos para \u00a0 resolver el presente asunto, mientras se acopiaba y evaluaba la prueba restante \u00a0 de las ordenadas en el auto de noviembre 22 de 2013. \u00a0 \u00a0<\/p>\n<p>5. Mediante escrito recibido por correo electr\u00f3nico en \u00a0 diciembre 6 de 2013, el Tribunal Administrativo de Boyac\u00e1 alleg\u00f3 un acta con el \u00a0 resumen de la audiencia realizada en diciembre 6 de 2013 con el doctor Germ\u00e1n \u00a0 Rivero Romero y la grabaci\u00f3n de dicha audiencia[2] \u00a0(fs. 100 y 101 ib.), constat\u00e1ndose preguntas y repuestas como las siguientes: \u00a0 \u00a0<\/p>\n<p>\u00a0\u201cPREGUNTA: explique las razones por las cuales en \u00a0 el a\u00f1o 2007, cuando entr\u00f3 en vigencia la Ley 1164 de 2007, y contaba con 57 a\u00f1os \u00a0 de edad, no inici\u00f3 los estudios pertinentes para certificar su idoneidad en la \u00a0 realizaci\u00f3n de endoscopias digestivas. \u00a0 \u00a0<\/p>\n<p>CONTEST\u00d3: Dificultad que existe en cursar una \u00a0 especialidad en medicina por la edad que ten\u00eda, 57 a\u00f1os de edad. A esa edad se \u00a0 tiene una serie de obligaciones familiares como deudas. Adem\u00e1s por el costo de \u00a0 la matr\u00edcula y el m\u00ednimo de a\u00f1os en que se cursa la especialidad y por el n\u00famero \u00a0 de cupos que otorgan las universidades, los cuales son muy pocos. \u00a0 \u00a0<\/p>\n<p>PREGUNTA: Informe al despacho donde se encuentra \u00a0 laborando actualmente y cu\u00e1les son los ingresos mensuales que recibe. \u00a0 \u00a0<\/p>\n<p>CONTEST\u00d3: A partir de la expedici\u00f3n de la Ley 1164 \u00a0 de 2007 los ingresos se vieron disminuidos, al momento tuve que vender \u00a0 consultorios que ten\u00eda a mi nombre, as\u00ed como el veh\u00edculo particular, para asumir \u00a0 deudas adquiridas. No estoy trabajando, depend\u00eda de dos hijos que me estaban \u00a0 ayudando y me he endeudado con algunos de mis amigos por lo que no dispongo de \u00a0 ning\u00fan ingreso. \u00a0 \u00a0<\/p>\n<p>Me forme en la endoscopia digestiva en el a\u00f1o 1991 y \u00a0 en la actualidad no puedo ejercer, no tengo ingresos.\u00a0 \u00a0 \u00a0<\/p>\n<p>PREGUNTA: \u00a0 \u00bfInforme al despacho si durante el tiempo que ha ejercido como m\u00e9dico realiz\u00f3 o \u00a0 se encuentra realizando cotizaciones y\/o aportes para pensi\u00f3n de vejez? En caso \u00a0 afirmativo a cu\u00e1l caja, fondo o entidad del sector p\u00fablico o privado. \u00a0 \u00a0<\/p>\n<p>CONTEST\u00d3: \u00a0 Soy v\u00edctima del cambio del Seguro Social a Colpensiones, tengo el tiempo \u00a0 cotizado, pero cuando solicite la revisi\u00f3n de la historia laboral se \u00a0 desaparecieron varios a\u00f1os (14) cotizados, tuve que demandar para el \u00a0 reconocimiento de mi pensi\u00f3n y no he recibido respuesta alguna. \u00a0 \u00a0<\/p>\n<p>Se le \u00a0 concede el uso de la palabra al declarante si tiene algo que agregar a la \u00a0 presente audiencia. \u00a0 \u00a0<\/p>\n<p>CONTEST\u00d3: Mi \u00a0 situaci\u00f3n es cr\u00edtica, para m\u00ed no es f\u00e1cil contar lo que me est\u00e1 pasando pero \u00a0 estoy esperando que se haga justicia.\u201d \u00a0 \u00a0<\/p>\n<p>II. CONSIDERACIONES DE LA CORTE \u00a0 CONSTITUCIONAL. \u00a0 \u00a0<\/p>\n<p>Esta \u00a0 corporaci\u00f3n es competente para examinar la determinaci\u00f3n referida, en Sala de \u00a0 Revisi\u00f3n, de conformidad con lo dispuesto en los art\u00edculos 86 y 241, numeral 9\u00b0 \u00a0 de la Constituci\u00f3n y 31 a 36 del Decreto 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>Segunda. El asunto objeto de \u00a0 an\u00e1lisis. \u00a0 \u00a0<\/p>\n<p>Seg\u00fan lo expuesto, esta Sala resolver\u00e1 si el \u00a0 Ministerio de Salud y Protecci\u00f3n Social y\/o la Secretar\u00eda de Salud de Boyac\u00e1 han \u00a0 vulnerado los derechos a la libre escogencia de profesi\u00f3n u oficio y al m\u00ednimo \u00a0 vital del m\u00e9dico Germ\u00e1n Rivero Romero, al abstenerse de habilitarlo profesionalmente para realizar \u00a0 endoscopias digestivas e impedirle as\u00ed laborar en esa espec\u00edfica \u00e1rea de la \u00a0 medicina, a pesar de tener las aptitudes para desempe\u00f1arse satisfactoriamente en \u00a0 dicha actividad, pues la ha llevado a cabo por m\u00e1s de 16 a\u00f1os y de la misma ha \u00a0 derivado su sustento y el de su familia. \u00a0 \u00a0<\/p>\n<p>La cuesti\u00f3n \u00a0 que se plantea conduce a precisar (i) la procedencia \u00a0 excepcional de la acci\u00f3n de tutela contra actos administrativos que violen derechos fundamentales; \u00a0 (ii) el derecho fundamental a la libre escogencia de \u00a0 profesi\u00f3n u oficio; (iii) por \u00faltimo, ser\u00e1 esclarecido \u00a0 el caso concreto. \u00a0 \u00a0<\/p>\n<p>Tercera. La procedencia \u00a0 excepcional de la acci\u00f3n de tutela contra actos administrativos que violen derechos fundamentales. \u00a0 \u00a0<\/p>\n<p>La acci\u00f3n de \u00a0 tutela se encuentra consagrada en el art\u00edculo 86 de la carta pol\u00edtica, como un \u00a0 mecanismo de protecci\u00f3n directa, inmediata y efectiva de los derechos \u00a0 fundamentales de las personas, cuando quiera que resulten vulnerados o \u00a0 amenazados por la acci\u00f3n u omisi\u00f3n de las autoridades p\u00fablicas, o de los \u00a0 particulares en los casos establecidos en la ley. \u00a0 \u00a0<\/p>\n<p>Teniendo una \u00a0 naturaleza subsidiaria y residual, la tutela solo procede (i) cuando no existe \u00a0 ninguna otra acci\u00f3n judicial por medio de la cual se pueda conjurar y superar la \u00a0 vulneraci\u00f3n de un derecho fundamental; (ii) aunque medie esa otra acci\u00f3n, si no \u00a0 deviene expedita, eficaz e id\u00f3nea para la protecci\u00f3n requerida; (iii) o si \u00a0 resulta imprescindible la intervenci\u00f3n del juez de tutela para evitar que se \u00a0 genere un perjuicio irremediable[3]. \u00a0 \u00a0<\/p>\n<p>Frente a lo \u00a0 anterior, en amplia jurisprudencia la Corte Constitucional ha reiterado, por \u00a0 regla general, la improcedencia de la tutela como mecanismo para la protecci\u00f3n \u00a0 de derechos fundamentales que podr\u00edan ser vulnerados o amenazados como \u00a0 consecuencia de la expedici\u00f3n de un acto administrativo, cuyo control ata\u00f1e a la \u00a0 respectiva jurisdicci\u00f3n contenciosa. \u00a0 \u00a0<\/p>\n<p>Con todo, \u00a0 pueden concurrir unas condiciones especiales que hacen procedente el amparo \u00a0 constitucional, si (i) de manera cierta emerge la amenaza o el da\u00f1o de magnitud \u00a0 sobre un derecho fundamental; (ii) que no exista forma de repararlo, de ocurrir, \u00a0 (iii) lo cual se aprecia inminente, (iv) convirtiendo en urgente e (v) \u00a0 impostergable e indispensable la protecci\u00f3n tutelar[4]. \u00a0 \u00a0<\/p>\n<p>Cuarta. \u00a0 El derecho fundamental a escoger libremente una profesi\u00f3n u oficio. Reiteraci\u00f3n \u00a0 de jurisprudencia. \u00a0 \u00a0<\/p>\n<p>4.1. El derecho a \u00a0 escoger profesi\u00f3n u oficio, consagrado en el art\u00edculo 26 superior[5], tiene que ser \u00a0 respetado, para que todas las personas puedan seleccionar libremente la \u00a0 actividad a la que van a dedicarse, de acuerdo con su vocaci\u00f3n, aptitud, \u00a0 habilidades e intereses, en condiciones de libertad e igualdad. As\u00ed lo ha \u00a0 predicado esta corporaci\u00f3n[6]: \u00a0 \u00a0<\/p>\n<p>\u201cEl art\u00edculo 26 de la Constituci\u00f3n establece dos derechos claramente \u00a0 definidos, esto es, el derecho a elegir profesi\u00f3n u oficio y el derecho a \u00a0 ejercer la actividad escogida. El primero es un acto de voluntariedad, \u00a0 pr\u00e1cticamente inmune a la injerencia estatal o particular, cuyo l\u00edmite es la \u00a0 elecci\u00f3n entre lo legalmente factible, mientras que el ejercicio de la libertad \u00a0 profesional es una faceta susceptible de mayor restricci\u00f3n, como quiera que \u00a0 involucra al individuo en la esfera de los derechos de los dem\u00e1s y el inter\u00e9s \u00a0 social, por lo que incluso puede estar sometido a la realizaci\u00f3n de servicios \u00a0 sociales obligatorios.\u201d \u00a0 \u00a0<\/p>\n<p>4.2. No \u00a0 existiendo derechos absolutos, la libertad de escoger profesi\u00f3n u oficio tambi\u00e9n \u00a0 tiene l\u00edmites, derivados especialmente de dos aspectos relevantes: (i) la \u00a0 posibilidad que tiene el legislador de exigir t\u00edtulos de idoneidad, para \u00a0 el ejercicio de aquellas profesiones que exijan especial capacitaci\u00f3n y \u00a0 formaci\u00f3n acad\u00e9mica, cuya raigambre constitucional guarda relaci\u00f3n y fundamento \u00a0 en el deber de las autoridades p\u00fablicas de proteger los derechos ciudadanos y \u00a0 consultar el inter\u00e9s general; (ii) la obligaci\u00f3n de las autoridades p\u00fablicas \u00a0 competentes, de inspeccionar y vigilar el ejercicio de tales profesiones \u00a0 u oficios, conforme a las normas establecidas al efecto. \u00a0 \u00a0<\/p>\n<p>Dichos l\u00edmites \u00a0 tienen reserva de ley, por lo que el legislador es el competente para establecer \u00a0 los diplomas de idoneidad que deben acompa\u00f1ar el ejercicio de las profesiones \u00a0 que los requieran y las condiciones en que se da la inspecci\u00f3n y vigilancia[7]. \u00a0 \u00a0<\/p>\n<p>\u201cDe hecho, no tiene sentido que la ley profesionalice ciertos oficios \u00a0 e imponga, como requisito para su ejercicio, un t\u00edtulo de idoneidad, si los \u00a0 riesgos de esa actividad no pueden ser claramente reducidos gracias a una \u00a0 formaci\u00f3n, pues, de no ser as\u00ed, la exigencia del t\u00edtulo ser\u00eda inadecuada e \u00a0 innecesaria. Por ende, s\u00f3lo puede limitarse el derecho a ejercer un oficio y \u00a0 exigirse un t\u00edtulo de idoneidad, cuando la actividad genera (i) un riesgo de \u00a0 magnitud considerable, (ii) susceptible de control o de disminuci\u00f3n a trav\u00e9s de \u00a0 una formaci\u00f3n acad\u00e9mica espec\u00edfica.\u201d \u00a0 \u00a0<\/p>\n<p>4.3. En la \u00a0 sentencia C-038 de enero 28 de 2003, M. P. Jaime Ara\u00fajo Renter\u00eda, esta \u00a0 corporaci\u00f3n estudi\u00f3 una demanda dirigida, entre otras, contra la expresi\u00f3n \u00a0 \u201cim\u00e1genes diagn\u00f3sticas\u201d, contenida en varios art\u00edculos de la Ley 657 de 2001[8], \u00a0 que se acus\u00f3 de inconstitucional por: \u00a0 \u00a0<\/p>\n<p>(i) Extender la \u00a0 necesidad de los requisitos de idoneidad de la radiolog\u00eda a las im\u00e1genes \u00a0 diagn\u00f3sticas, desconociendo innecesaria y desproporcionadamente, seg\u00fan el actor, \u00a0 el derecho previsto en el art\u00edculo 26 superior a la libertad de ejercer una \u00a0 profesi\u00f3n u oficio, especialmente porque con ello se impide al personal m\u00e9dico \u00a0 en general, realizar im\u00e1genes diagn\u00f3sticas que no tienen mayor riesgo social. \u00a0 \u00a0<\/p>\n<p>(ii) Por vulnerar \u00a0 el derecho a la igualdad, al establecer injustificados privilegios en favor de \u00a0 los profesionales m\u00e9dicos especializados en esas competencias, desconociendo a \u00a0 quienes contaban con habilidades en tales \u00e1reas, aunque no con el t\u00edtulo. \u00a0 \u00a0<\/p>\n<p>(iii) Por \u00a0 conculcar el inter\u00e9s general y los derechos adquiridos de los galenos \u00a0 capacitados, al desconocer que en poblaciones del pa\u00eds que no cuenten con este \u00a0 tipo especialistas, los pacientes se ver\u00edan privados sin justificaci\u00f3n de los \u00a0 beneficios que se pueden obtener con las im\u00e1genes diagn\u00f3sticas, tomadas por \u00a0 parte de m\u00e9dicos generales o param\u00e9dicos. \u00a0 \u00a0<\/p>\n<p>En el estudio \u00a0 realizado por esta corporaci\u00f3n, se concluy\u00f3 que la obtenci\u00f3n de im\u00e1genes \u00a0 diagn\u00f3sticas involucra no s\u00f3lo la manipulaci\u00f3n t\u00e9cnica de aparatos m\u00e9dicos sino, \u00a0 especialmente, la interpretaci\u00f3n de las im\u00e1genes obtenidas, lo que conlleva la \u00a0 emisi\u00f3n de un diagn\u00f3stico cl\u00ednico relacionado con ellas. Este diagn\u00f3stico \u00a0 resulta ser un aspecto delicado para el paciente y tan relacionado directamente \u00a0 con la salud y el tratamiento oportuno, que para la Corte implica un \u201criesgo \u00a0 social evidente y, tambi\u00e9n, un riesgo de lesi\u00f3n de derechos fundamentales como \u00a0 son la vida y la integridad personal\u201d. \u00a0 \u00a0<\/p>\n<p>En tal sentido, \u00a0 este tribunal explic\u00f3 que la restricci\u00f3n impuesta por el legislador al ejercicio \u00a0 de la profesi\u00f3n m\u00e9dica en esa \u00e1rea, se ajustaba a lo establecido en el art\u00edculo \u00a0 26 superior. Adem\u00e1s, indic\u00f3 que la disposici\u00f3n no vulneraba la igualdad entre \u00a0 los galenos, ni sus derechos adquiridos, ya que la norma cobijaba a los dem\u00e1s \u00a0 m\u00e9dicos especializados que acreditaran formaci\u00f3n profesional en estas \u00e1reas. Al \u00a0 respecto se precis\u00f3 en la citada sentencia: \u00a0 \u00a0<\/p>\n<p>\u201cCabe se\u00f1alar que la ley citada no es prohibitiva y, en cambio, es \u00a0 permisiva, en la medida en que los m\u00e9dicos de las otras especialidades pueden \u00a0 ejercer la radiolog\u00eda e im\u00e1genes diagn\u00f3sticas, conforme a lo previsto en los \u00a0 mencionados arts. 4\u00ba y 11, y en cuanto adem\u00e1s se\u00f1ala un per\u00edodo de transici\u00f3n de \u00a0 4 a\u00f1os, que es m\u00e1s que suficiente para que los m\u00e9dicos interesados en \u00a0 desarrollar dichas actividades puedan prepararse\u201d. \u00a0 \u00a0<\/p>\n<p>4.4. De otra \u00a0 parte, en la sentencia T-167 de marzo 9 de 2007, M. P. Manuel Jos\u00e9 Cepeda \u00a0 Espinosa, se estudi\u00f3 el caso de un galeno especialista en salud familiar, que \u00a0 interpuso una acci\u00f3n de tutela contra la Secretar\u00eda de Salud de Boyac\u00e1, por \u00a0 considerar que esa entidad le estaba vulnerando sus derechos fundamentales al \u00a0 debido proceso, defensa, trabajo e igualdad, al denegarle la habilitaci\u00f3n \u00a0 profesional que exige la ley para laborar como m\u00e9dico en las \u00e1reas de radiolog\u00eda \u00a0 e im\u00e1genes diagn\u00f3sticas. \u00a0 \u00a0<\/p>\n<p>En dicho asunto, \u00a0 los argumentos expuestos por la Secretar\u00eda de Salud de Boyac\u00e1 se fundamentaban \u00a0 en que \u201ca la especialidad [en Salud Familiar] no le es propio la aplicaci\u00f3n \u00a0 de dichos procedimientos diagn\u00f3sticos\u201d y que la Fundaci\u00f3n Universitaria del \u00a0 \u00c1rea Andina, donde el actor curs\u00f3 dicha especialidad, no cumpl\u00eda con el Decreto \u00a0 1665 de 2002, pues en su pensum \u00a0no proporcionaba los conocimientos del manejo e interpretaci\u00f3n del espectro \u00a0 electromagn\u00e9tico, del ultrasonido especialmente, as\u00ed como de las radiaciones \u00a0 ionizantes para establecer el diagn\u00f3stico y\/o el tratamiento de las enfermedades \u00a0 inherentes a sus especialidades. \u00a0 \u00a0<\/p>\n<p>Para el entonces \u00a0 demandante, dichas afirmaciones eran contrarias a la ley y violatorias de sus \u00a0 derechos fundamentales, ya que (i) el par\u00e1grafo del art\u00edculo 4\u00ba de la Ley 657 de \u00a0 2001, que fija quienes pueden o no realizar tales actividades diagn\u00f3sticas, no \u00a0 except\u00faa expresamente a ning\u00fan m\u00e9dico especialista; (ii) el Ministerio de \u00a0 Educaci\u00f3n Nacional, con oficio 004681 de mayo 23 de 2006, acept\u00f3 las \u00a0 modificaciones que la Fundaci\u00f3n Universitaria del \u00c1rea Andina introdujo en el \u00a0 pensum de la Especializaci\u00f3n en Salud Familiar, con un \u00e9nfasis en \u00a0 ultrasonido, por \u00e9l cursadas. Por ello, consideraba que cumpl\u00eda con las \u00a0 competencias exigidas por la ley para laborar en im\u00e1genes diagn\u00f3sticas, lo cual \u00a0 fue constatado por la Corte en el tr\u00e1mite de revisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>As\u00ed, fueron \u00a0 transitoriamente tutelados los derechos del actor a la igualdad y a la libre \u00a0 escogencia de profesi\u00f3n u oficio, inaplic\u00e1ndose la Resoluci\u00f3n de la Secretar\u00eda \u00a0 de Salud de Boyac\u00e1 que lo inhabilitaba para el ejercicio profesional en im\u00e1genes \u00a0 diagn\u00f3sticas, hasta tanto se resolviera la controversia en la jurisdicci\u00f3n \u00a0 contencioso administrativa, debiendo el demandante ejercer la acci\u00f3n \u00a0 correspondiente en un t\u00e9rmino m\u00e1ximo de cuatro (4) meses. \u00a0 \u00a0<\/p>\n<p>4.5. En fallo T-040 de febrero 2 de 2012, M.P. Mar\u00eda Victoria Calle \u00a0 Correa, se analiz\u00f3 el caso de un m\u00e9dico que hab\u00eda presentado una acci\u00f3n de \u00a0 tutela contra el Centro M\u00e9dico Imbanaco de Cali, al considerar que le estaban \u00a0 vulnerando sus derechos fundamentales a escoger y ejercer libremente profesi\u00f3n u \u00a0 oficio, al trabajo, al libre desarrollo de la personalidad y a la igualdad, con \u00a0 la negativa a posibilitarle fungir como endoscopista en dicho centro, a pesar de \u00a0 alegar cumplir con todos los requisitos constitucionales, legales, \u00a0 reglamentarios y acad\u00e9micos necesarios para ello. \u00a0 \u00a0<\/p>\n<p>Por su parte, en las disposiciones reglamentarias del Centro M\u00e9dico \u00a0 Imbanaco se encontraba dispuesto (arts. 8\u00b0 a 13 del Reglamento de Funcionamiento \u00a0 del Centro), que el Comit\u00e9 de Admisiones contaba con la potestad discrecional de \u00a0 seleccionar a los miembros del cuerpo m\u00e9dico y otorgar las prerrogativas de \u00a0 ejercicio correspondientes, con fundamento en la valoraci\u00f3n tanto de sus \u00a0 credenciales acad\u00e9micas como de su experiencia, as\u00ed como en el consenso y \u00a0 acuerdo de los miembros del cuerpo m\u00e9dico. \u00a0 \u00a0<\/p>\n<p>Sobre tal cuesti\u00f3n, la Corte destac\u00f3 que las instituciones \u00a0 prestadoras de servicios de salud, \u201cdeben necesariamente contar con un margen \u00a0 de discrecionalidad amplio para seleccionar a aquellos profesionales que cumplan \u00a0 con los criterios por ellas establecidos en sus Reglamentos, de conformidad con \u00a0 la legislaci\u00f3n aplicable, con miras a conformar el equipo de m\u00e9dicos y dem\u00e1s \u00a0 profesionales de la salud que mejor responda a las necesidades del servicio y al \u00a0 est\u00e1ndar de calidad institucional fijado, en especial, por las exigencias del \u00a0 derecho fundamental a la salud de los pacientes que acudir\u00e1n a sus servicios\u201d. \u00a0 \u00a0<\/p>\n<p>Con todo, la Corte precis\u00f3 que el l\u00edmite a este importante margen de \u00a0 discrecionalidad en la selecci\u00f3n profesional est\u00e1 dado por la prohibici\u00f3n \u00a0 constitucional de la discriminaci\u00f3n. Es decir, las instituciones prestadoras de \u00a0 salud encuentran un l\u00edmite a su potestad de seleccionar a los profesionales que \u00a0 vincular\u00e1n o habilitar\u00e1n, en la prohibici\u00f3n de incurrir en diferenciaciones o \u00a0 exclusiones basadas en criterios constitucionalmente proscritos, tales como el \u00a0 sexo, la raza, el origen nacional o familiar, la orientaci\u00f3n sexual, la lengua, \u00a0 la religi\u00f3n, el origen \u00e9tnico, la opini\u00f3n pol\u00edtica o filos\u00f3fica, u otros motivos \u00a0 de distinci\u00f3n que no compaginen con el principio constitucional de igualdad. \u00a0 \u00a0<\/p>\n<p>En la resoluci\u00f3n del caso concreto, esta corporaci\u00f3n observ\u00f3 que el \u00a0 actor pretend\u00eda demostrar sus credenciales acad\u00e9micas y su experiencia \u00a0 profesional en el campo de la cirug\u00eda endosc\u00f3pica, solicit\u00e1ndole al juez de \u00a0 tutela que determinara que s\u00ed llenaba los requisitos reglamentarios del cuerpo \u00a0 profesional del Centro M\u00e9dico Imbanaco, pero esta Corte aclar\u00f3 que carec\u00eda de \u00a0 competencia \u201cpara convalidar, valorar o siquiera pronunciarse sobre la \u00a0 validez, importancia, aceptabilidad u otras caracter\u00edsticas de la preparaci\u00f3n \u00a0 profesional\u201d del demandante y neg\u00f3 el \u00a0 amparo reclamado. \u00a0 \u00a0<\/p>\n<p>4.6. Con \u00a0 fundamento en todo lo anterior, reit\u00e9rese que la medicina es una actividad \u00a0 profesional cuya pr\u00e1ctica implica elevado riesgo social y un impacto \u00a0 significativo en los derechos de los asociados; consecuentemente, su ejercicio y \u00a0 el de sus diversas especialidades requieren t\u00edtulos de aptitud, que acrediten \u00a0 los conocimientos t\u00e9cnicos necesarios para la realizaci\u00f3n id\u00f3nea de las \u00a0 actividades correspondientes. Adem\u00e1s, las autoridades p\u00fablicas est\u00e1n habilitadas \u00a0 para vigilar e inspeccionar el ejercicio de tal profesi\u00f3n y sus especialidades, \u00a0 conforme a las exigencias normativas. \u00a0 \u00a0<\/p>\n<p>Quinta. Caso \u00a0 concreto. \u00a0 \u00a0<\/p>\n<p>5.1. En el \u00a0 presente asunto, las corporaciones judiciales de instancia dedujeron que el \u00a0 doctor Germ\u00e1n Rivero Romero pod\u00eda acudir a una acci\u00f3n contenciosa \u00a0 administrativa, para debatir la legalidad del oficio expedido por la Secretar\u00eda \u00a0 de Salud de Boyac\u00e1 en octubre 22 de 2012, que le neg\u00f3 la autorizaci\u00f3n para \u00a0 realizar procedimientos de endoscop\u00eda digestiva, acci\u00f3n dentro de la cual es \u00a0 posible, adem\u00e1s, pedir la suspensi\u00f3n provisional del acto acusado. \u00a0 \u00a0<\/p>\n<p>Por ello, \u00a0 la Sala de Revisi\u00f3n debe resolver previamente si en realidad el demandante \u00a0 desatendi\u00f3 el principio de subsidiariedad, al no haber incoado esa acci\u00f3n \u00a0 regular, en lugar de adelantarse a formular la solicitud de tutela. \u00a0 \u00a0<\/p>\n<p>No puede negarse la existencia \u00a0 de ese otro medio de defensa judicial de los derechos invocados ante la \u00a0 jurisdicci\u00f3n de lo contencioso administrativo, dado que la decisi\u00f3n de la \u00a0 Secretar\u00eda de Salud de Boyac\u00e1, que neg\u00f3 la habilitaci\u00f3n profesional del actor \u00a0 para realizar endoscopias digestivas, es sin duda un acto administrativo, que \u00a0 puede demandarse en acci\u00f3n de nulidad y restablecimiento del derecho, que \u00a0 permite pedir la suspensi\u00f3n provisional del acto acusado. \u00a0 \u00a0<\/p>\n<p>Con todo, el juez de tutela \u00a0 est\u00e1 habilitado para examinar en concreto si quien pide el amparo se encuentra \u00a0 frente a un perjuicio irremediable y si los medios comunes de protecci\u00f3n son \u00a0 suficientes o no en las circunstancias espec\u00edficas, que para el caso son las de \u00a0 un galeno que no solamente afronta la imposibilidad de seguir realizando la \u00a0 pr\u00e1ctica profesional en la que durante m\u00e1s de tres lustros se ha distinguido, \u00a0 sino que podr\u00eda perder la destreza y, consecuencialmente, la clientela \u00a0 potencial, al saberse en la comunidad para la cual laboraba que se hab\u00eda quedado \u00a0 sin autorizaci\u00f3n para continuar efectuando el procedimiento m\u00e9dico en el que era \u00a0 reconocido. \u00a0 \u00a0<\/p>\n<p>Sea o no otorgable el amparo \u00a0 constitucional, es lo cierto que est\u00e1n en inminente riesgo no solo la libertad \u00a0 de escoger y ejercer una profesi\u00f3n, sino el m\u00ednimo vital propio y de la familia, \u00a0 de quien se ve impelido a dejar de ejercer la labor profesional de la que \u00a0 derivaba el sustento personal y familiar. \u00a0 \u00a0<\/p>\n<p>En tal sentido, la consabida \u00a0 duraci\u00f3n prolongada de un proceso de nulidad y restablecimiento del derecho ante \u00a0 la jurisdicci\u00f3n de lo contencioso administrativo, con incertidumbre sobre la \u00a0 suspensi\u00f3n del acto administrativo correspondiente, enfrenta al actor a un lapso \u00a0 de a\u00f1os \u00a0en que no podr\u00e1 ejercer su profesi\u00f3n como m\u00e9dico endoscopista, \u00a0 circunstancia que incidir\u00e1 sin lugar a dudas en su m\u00ednimo vital y el de su \u00a0 familia, que depende econ\u00f3micamente de \u00e9l. Lo que debe determinarse es, \u00a0 entonces, si la determinaci\u00f3n que lesiona sus derechos es arbitraria o, por el \u00a0 contrario, est\u00e1 jur\u00eddicamente fundamentada.\u00a0 \u00a0 \u00a0<\/p>\n<p>En consecuencia, la acci\u00f3n de \u00a0 tutela bajo estudio s\u00ed es procedente, debiendo la Corte entrar a determinar, de \u00a0 fondo, si corresponde concederla. \u00a0 \u00a0<\/p>\n<p>5.2. De tal forma, se estudiar\u00e1 \u00a0 si el Ministerio de Salud y Protecci\u00f3n Social y la Secretar\u00eda de Salud de Boyac\u00e1 \u00a0 han vulnerado, de manera contraria a Derecho, la libertad de escoger profesi\u00f3n u \u00a0 oficio y el m\u00ednimo vital del doctor Germ\u00e1n Rivero Romero, ante la negativa de \u00a0 habilitaci\u00f3n profesional para la realizaci\u00f3n de endoscopias digestivas, \u00a0 impidi\u00e9ndosele as\u00ed laborar en esa espec\u00edfica \u00e1rea de la medicina, a pesar de \u00a0 aducir tener la aptitud para desempe\u00f1arse satisfactoriamente en dicha actividad, \u00a0 que ha llevado a cabo durante m\u00e1s de 16 a\u00f1os, derivado de all\u00ed su sustento y el \u00a0 de su familia. \u00a0 \u00a0<\/p>\n<p>Al revisar las actuaciones del \u00a0 Ministerio de Salud y Protecci\u00f3n Social y de la Secretar\u00eda de Salud de Boyac\u00e1, \u00a0 frente a la negativa de permitirle al actor su habilitaci\u00f3n profesional para la \u00a0 realizaci\u00f3n de endoscopias digestivas, se observa que la decisi\u00f3n de esas \u00a0 entidades p\u00fablicas corresponden a lo establecido en el par\u00e1grafo 2\u00b0 del art\u00edculo \u00a0 18 de la Ley 1164 de 2007, que estipula con respecto a los requisitos para el \u00a0 ejercicio de las profesiones y ocupaciones del \u00e1rea de la salud: \u201cQuienes a \u00a0 la vigencia de la presente ley se encuentren ejerciendo competencias propias de \u00a0 especialidades, subespecialidades y ocupaciones del \u00e1rea de la salud sin el \u00a0 t\u00edtulo o certificado correspondiente, contar\u00e1n por una sola vez con un per\u00edodo \u00a0 de tres a\u00f1os para acreditar la norma de competencia acad\u00e9mica correspondiente \u00a0 expedida por una instituci\u00f3n legalmente reconocida por el Estado.\u201d \u00a0 \u00a0<\/p>\n<p>5.3. Por su parte, las \u00a0 dependencias accionadas actuaron leg\u00edtimamente, amparadas en las disposiciones \u00a0 del anexo 1\u00b0 de la Resoluci\u00f3n 1043 de abril 3 de 2006 (\u201cpor la cual se \u00a0 establecen las condiciones que deben cumplir los prestadores de servicios de \u00a0 salud para habilitar sus servicios e implementar el componente de auditoria para \u00a0 el mejoramiento de la calidad de la atenci\u00f3n\u201d), la cual establece \u00a0 como requisitos para la realizaci\u00f3n de endoscopias digestivas que la lleven a \u00a0 cabo \u201cM\u00e9dicos especializados en gastronterolog\u00eda, gastroenterolog\u00eda \u00a0 pedi\u00e1trica, pediatr\u00eda, coloproctolog\u00eda, cirug\u00eda pedi\u00e1trica, cirug\u00eda general con \u00a0 subespecialidad en gastroenterolog\u00eda que en su formaci\u00f3n demuestren bajo \u00a0 certificaci\u00f3n, a excepci\u00f3n de los gastroenter\u00f3logos, gastroenter\u00f3logos pediatras \u00a0 o coloproct\u00f3logos haber recibido entrenamiento de un a\u00f1o en endoscopia de v\u00edas \u00a0 digestivas certificado por una Instituci\u00f3n de Educaci\u00f3n Superior reconocida por \u00a0 el Estado\u201d. \u00a0 \u00a0<\/p>\n<p>No se colige de dicha \u00a0 preceptiva alguna manifiesta incompatibilidad frente a normas superiores, de la \u00a0 que pudiere derivarse su inaplicaci\u00f3n (art. 4\u00b0 Const.), ni que la experiencia y \u00a0 otros cursos del galeno puedan ser tenidos como medios suced\u00e1neos de la \u00a0 capacitaci\u00f3n v\u00e1lidamente exigida. Tal consideraci\u00f3n deviene, de otra parte, \u00a0 reafirmada con lo previamente expuesto, como el concepto de la Asociaci\u00f3n \u00a0 Colombiana de Endoscopia Digestiva. \u00a0 \u00a0<\/p>\n<p>\u201cHan sido m\u00faltiples las manifestaciones por la cuales se ha llegado a \u00a0 un consenso para no recomendar que se siga permitiendo la pr\u00e1ctica de la \u00a0 endoscopia digestiva, ni siquiera la b\u00e1sica diagn\u00f3stica, con tan poco tiempo de \u00a0 preparaci\u00f3n\u2026 \u00a0 \u00a0<\/p>\n<p>No es el criterio central para avalar la adecuada formaci\u00f3n en \u00a0 endoscopia digestiva el certificar un n\u00famero determinado de procedimientos. Son \u00a0 las caracter\u00edsticas acad\u00e9micas, tecnol\u00f3gicas supervisadas con seguimiento, \u00a0 investigadas, las que vuelven a un determinado n\u00famero de procedimientos \u00a0 efectivamente en una evidencia de adecuada formaci\u00f3n\u2026 \u00a0 \u00a0<\/p>\n<p>Estas consideraciones relativas al tipo de formaci\u00f3n previa y a los \u00a0 tiempos m\u00ednimos de formaci\u00f3n no surgieron de forma prejuiciosa\u2026 la endoscopia \u00a0 digestiva se aprecia como parte de toda una formaci\u00f3n integral dentro de las \u00a0 especialidades gastroenterolog\u00edas mencionadas previamente.\u201d \u00a0 \u00a0<\/p>\n<p>5.4. De acuerdo con lo \u00a0 expuesto, permitirle al doctor Germ\u00e1n Rivero Romero que contin\u00fae la pr\u00e1ctica sin \u00a0 el correspondiente t\u00edtulo de posgrado, constituir\u00eda una excepci\u00f3n que, de una \u00a0 parte, vulnerar\u00eda el derecho a la igualdad, frente a otros profesionales que \u00a0 estando en equiparables condiciones a las del actor (edad, experiencia, \u00a0 responsabilidades laborales y familiares), s\u00ed cursaron la especializaci\u00f3n \u00a0 adecuada, lo cual tambi\u00e9n ha podido realizar el demandante durante el tiempo \u00a0 normativamente concedido al efecto, para consolidar la idoneidad, que as\u00ed mismo \u00a0 se garantice a los pacientes. \u00a0 \u00a0<\/p>\n<p>Adem\u00e1s, el doctor Germ\u00e1n Rivero \u00a0 Romero puede ocuparse en otras actividades m\u00e9dicas que no requieran ese t\u00edtulo \u00a0 de especializaci\u00f3n, mientras que, de otra parte, \u00e9l mismo expres\u00f3 que cuenta con \u00a0 tiempo cotizado para que se le reconozca pensi\u00f3n, habiendo presentado una \u00a0 demanda al respecto (fs. 100 y 101 cd. Corte). \u00a0\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>5.5. En consecuencia, se \u00a0 modificar\u00e1 el fallo proferido en marzo 22 de 2013 por \u00a0 la Secci\u00f3n Cuarta de la Sala de lo Contencioso Administrativo del Consejo de \u00a0 Estado, que confirm\u00f3 el dictado en febrero 21 de 2013 por el \u00a0 Tribunal Administrativo de Boyac\u00e1, declarando improcedente la acci\u00f3n de tutela, \u00a0 para en su lugar resolver de fondo lo demandado y negar la acci\u00f3n de tutela \u00a0 instaurada mediante apoderado por el doctor Germ\u00e1n Rivero Romero, contra el \u00a0 Ministerio de Salud y Protecci\u00f3n Social y la Secretar\u00eda de Salud de Boyac\u00e1. \u00a0 \u00a0<\/p>\n<p>II.- DECISI\u00d3N. \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Sexta \u00a0 de Revisi\u00f3n de la Corte Constitucional, administrando justicia en nombre del \u00a0 pueblo y por mandato de la Constituci\u00f3n, \u00a0 \u00a0<\/p>\n<p>RESUELVE \u00a0 \u00a0<\/p>\n<p>Primero.- LEVANTAR \u00a0la suspensi\u00f3n de t\u00e9rminos que, mediante auto de \u00a0 fecha diciembre 2 de 2013, se hab\u00eda dispuesto en la \u00a0 presente acci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Segundo.- MODIFICAR\u00a0el fallo proferido en marzo 22 de 2013 por la Secci\u00f3n \u00a0 Cuarta de la Sala de lo Contencioso Administrativo del Consejo de Estado, que confirm\u00f3 el dictado en \u00a0 febrero 21 de 2013 por el Tribunal Administrativo de Boyac\u00e1, declarando \u00a0 improcedente la acci\u00f3n, para NEGAR la tutela solicitada mediante \u00a0 apoderado por el doctor Germ\u00e1n Rivero Romero, identificado con c\u00e9dula de \u00a0 ciudadan\u00eda 19\u2019129.186 de Bogot\u00e1, contra el Ministerio de Salud y Protecci\u00f3n \u00a0 Social y la Secretar\u00eda de Salud de Boyac\u00e1. \u00a0 \u00a0<\/p>\n<p>Tercero.- Por Secretar\u00eda General, L\u00cdBRESE la comunicaci\u00f3n a que se \u00a0 refiere el art\u00edculo 36 del Decreto 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>Notif\u00edquese, \u00a0 comun\u00edquese, publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>NILSON PINILLA PINILLA \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>JORGE IGNACIO PRETELT CHALJUB \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>ALBERTO ROJAS R\u00cdOS \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA DE MONCALEANO \u00a0 \u00a0<\/p>\n<p>Secretaria General \u00a0 \u00a0<\/p>\n<p>[1] En la elaboraci\u00f3n de dicho consenso participaron: \u201cDirectores \u00a0 (o sus representantes) de programas de postgrado (gastroenterolog\u00eda y endoscopia \u00a0 digestiva, cirug\u00eda gastrointestinal y endoscopia digestiva, coloproctolog\u00eda) \u00a0 acreditados en Colombia: Arango L\u00e1zaro (Univ. de Caldas); Hani Albis (Pont. \u00a0 Univ. Javeriana); Oliveros Ricardo (Univ. Militar Nueva Granada-Inst. Nal. de \u00a0 Cancerolog\u00eda); Pe\u00f1aloza Ram\u00edrez Arecio (Univ. de Ciencias de la Salud); Rey \u00a0 Tovar Mario (Univ. del Rosario); Sabbagh Luis Carlos (Fund. Universitaria \u00a0 Sanitas); Salej Jorge (Univ. Militar Nueva Granada-Hosp. Militar Central); \u00a0 Santacoloma Mario (Univ. de Caldas). Presidentes (o sus representantes) de \u00a0 Asociaciones Cient\u00edficas de Enfermedades Digestivas en Colombia: Aponte Diego \u00a0 (Asociaci\u00f3n Colombiana de Endoscopia Digestiva); Archila Paulo Emilio \u00a0 (Asociaci\u00f3n Colombiana de Medicina Interna); Galiano Mar\u00eda Teresa (Asociaci\u00f3n \u00a0 Colombiana de Gastroenterolog\u00eda); Ib\u00e1\u00f1ez Heinz (Asociaci\u00f3n Colombiana de \u00a0 Coloproctolog\u00eda); Landaz\u00e1bal Gustavo (Asociaci\u00f3n Colombiana de Cirug\u00eda). \u00a0 Expresidentes Asociaciones Cient\u00edficas de Enfermedades Digestivas en Colombia: \u00a0 Alvarado Jaime; Aponte Luciano; Cuello Eduardo; Gil Parada Fabio Leonel; \u00a0 Pe\u00f1aloza Rosas Arecio; Plata Guillermo; Rojas Elsa; Rold\u00e1n Luis Fernando. \u00a0 Vicepresidente Asociaci\u00f3n Iberoamericana de Enfermer\u00eda en Gastroenterolog\u00eda y \u00a0 Endoscopia (ASIEGE): Ruiz Flor Alba. Train the Trainers &#8211; Organizaci\u00f3n Mundial \u00a0 de Gastroenterolog\u00eda: Emura Fabi\u00e1n; Valdivieso Rueda Eduardo; Vargas R\u00f3mulo. \u00a0 Docentes y L\u00edderes de Opini\u00f3n: Blanco Camilo; Ca\u00f1adas Ra\u00fal; Solano Jaime; \u00a0 Unigarro Iv\u00e1n; V\u00e9lez Fausto. Jefes de Residentes de Programas acreditados en \u00a0 gastroenterolog\u00eda: Casas Fernando (Cirujano); Herr\u00e1n Martha (Internista); Imbeth \u00a0 Pedro (Internista); Su\u00e1rez Juliana (Cirujana).\u201d \u00a0 \u00a0<\/p>\n<p>[2] \u00a0http:\/\/youtu.be\/kUGZoX6Cr0c \u00a0 \u00a0<\/p>\n<p>[3] \u00a0Cfr. T-722 de septiembre 13 de 2010, M. P. Jorge Ignacio Pretelt Chaljub, entre \u00a0 otras. \u00a0 \u00a0<\/p>\n<p>[4] \u00a0Cfr. T-731 de octubre 15 de 2009, M. P. Humberto Antonio Sierra \u00a0 Porto, entre otras. \u00a0 \u00a0<\/p>\n<p>[5] \u00a0Art. 26 Const.: \u201cToda persona es libre de escoger profesi\u00f3n u oficio. La Ley \u00a0 podr\u00e1 exigir t\u00edtulos de idoneidad. Las autoridades competentes inspeccionar\u00e1n y \u00a0 vigilar\u00e1n el ejercicio de las profesiones. Las ocupaciones, artes y oficios que \u00a0 no exijan formaci\u00f3n acad\u00e9mica son de libre ejercicio, salvo aquellas que \u00a0 impliquen un riesgo social. Las profesiones legalmente reconocidas pueden \u00a0 organizarse en colegios. La estructura interna y el funcionamiento de estos, \u00a0 deber\u00e1 ser democr\u00e1tico. La ley podr\u00e1 asignarles funciones p\u00fablicas y establecer \u00a0 los debidos controles.\u201d \u00a0 \u00a0<\/p>\n<p>[6] \u00a0C-031 de enero 29 de 1999, M. P. Alejandro Mart\u00ednez Caballero. \u00a0 \u00a0<\/p>\n<p>[7] \u00a0Cfr. T-167 de marzo 9 de 2007, M. P. Manuel Jos\u00e9 Cepeda Espinosa, entre otras. \u00a0 \u00a0<\/p>\n<p>[8] \u00a0\u201cPor la cual se reglamenta la especialidad m\u00e9dica de la radiolog\u00eda e im\u00e1genes \u00a0 diagn\u00f3sticas y se dictan otras disposiciones.\u201d<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-346A-14 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 Sentencia T-346A\/14 \u00a0 \u00a0 ACCION DE TUTELA CONTRA \u00a0 ACTO ADMINISTRATIVO-Procedencia \u00a0 excepcional cuando amenaza derechos fundamentales\u00a0 \u00a0 \u00a0 En amplia \u00a0 jurisprudencia la Corte Constitucional ha reiterado, por regla general, la \u00a0 improcedencia de la tutela como mecanismo para la protecci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[99],"tags":[],"class_list":["post-21696","post","type-post","status-publish","format-standard","hentry","category-tutelas-2014"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/21696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=21696"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/21696\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=21696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=21696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=21696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}