{"id":22380,"date":"2024-06-26T17:33:07","date_gmt":"2024-06-26T17:33:07","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/06\/26\/su553-15\/"},"modified":"2024-06-26T17:33:07","modified_gmt":"2024-06-26T17:33:07","slug":"su553-15","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/su553-15\/","title":{"rendered":"SU553-15"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0SU553-15 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia SU553\/15 \u00a0 \u00a0<\/p>\n<p>(Bogot\u00e1, D.C., 27 \u00a0 de agosto) \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA \u00a0 PROVIDENCIAS JUDICIALES-Requisitos generales y especiales de procedibilidad \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA FRENTE A ACTOS \u00a0 ADMINISTRATIVOS EN MATERIA DE CONCURSO DE MERITOS-Procedencia excepcional \u00a0 para evitar perjuicio irremediable por cuanto lista de elegibles pierde vigencia \u00a0 \u00a0<\/p>\n<p>La jurisprudencia constitucional ha determinado que \u00a0 existen casos excepcionales en los que no opera la regla general de \u00a0 improcedencia de la acci\u00f3n de tutela contra este tipo de actos administrativos. \u00a0 El primer supuesto, es cuando el medio de defensa existe, pero en la pr\u00e1ctica es \u00a0 ineficaz para amparar el derecho fundamental cuya protecci\u00f3n se invoca y que en \u00a0 caso de no ser garantizado, se traduce en un claro perjuicio para el actor; y el \u00a0 segundo, cuando el accionante ejerce la acci\u00f3n de tutela como mecanismo \u00a0 transitorio para evitar un perjuicio irremediable, el cual debe cumplir con los \u00a0 requisitos de ser inminente, de requerir medidas urgentes, de ser grave y de ser \u00a0 impostergable. De ah\u00ed que, en ciertos casos, cuando la acci\u00f3n de tutela se \u00a0 interpone contra actos administrativos relacionados con concursos de m\u00e9ritos, el \u00a0 perjuicio irremediable que se pretender\u00eda evitar son las consecuencias negativas \u00a0 que se derivan de la p\u00e9rdida de vigencia de la lista de elegibles, las cuales no \u00a0 se podr\u00edan impedir si exige al tutelante el previo agotamiento de los medios de \u00a0 control dispuestos en la jurisdicci\u00f3n de lo contencioso administrativo para \u00a0 reclamar la protecci\u00f3n de su derecho, por la extensa duraci\u00f3n de su tr\u00e1mite. \u00a0 \u00a0<\/p>\n<p>DEBIDO PROCESO ADMINISTRATIVO EN \u00a0 CONCURSO DE MERITOS-Vulneraci\u00f3n por Corte Suprema de Justicia al no aplicar \u00a0 actos administrativos que definieron la naturaleza y la forma en que se deb\u00edan \u00a0 proveer las plazas para Magistrados especializados en restituci\u00f3n de tierras \u00a0 \u00a0<\/p>\n<p>Es claro que la provisi\u00f3n de los cargos de la Rama \u00a0 Judicial se debe hacer a trav\u00e9s de las reglas del concurso p\u00fablico y abierto \u00a0 contenido en la Ley 270 de 1996 y, teniendo en cuenta la lista de elegibles \u00a0 vigente. En todo caso, la vocaci\u00f3n transitoria del cargo no podr\u00e1 entenderse \u00a0 como impedimento, para que, en la selecci\u00f3n del funcionario que lo vaya ocupar, \u00a0 se aplique el r\u00e9gimen de carrera judicial. Dicho r\u00e9gimen protege los derechos y \u00a0 garant\u00edas constitucionales de aspirantes y servidores p\u00fablicos, al mismo tiempo \u00a0 que, cumple los fines estatales de transparencia y eficacia, comprometidos en \u00a0 los mecanismos de ingreso al servicio p\u00fablico. \u00a0 \u00a0<\/p>\n<p>SALA ADMINISTRATIVA DEL CONSEJO \u00a0 SUPERIOR DE LA JUDICATURA-Competencia constitucional para reglamentar y \u00a0 administrar la carrera judicial \u00a0 \u00a0<\/p>\n<p>CONSEJO SUPERIOR DE LA \u00a0 JUDICATURA Y FACULTAD DE REGLAMENTAR LA CARRERA JUDICIAL-Potestad \u00a0 reglamentaria de los \u00f3rganos constitucionales \u00a0 \u00a0<\/p>\n<p>CARGOS EN LA RAMA JUDICIAL-Provisi\u00f3n \u00a0 en propiedad, en provisionalidad o en encargo \u00a0 \u00a0<\/p>\n<p>MAGISTRADOS ESPECIALIZADOS EN \u00a0 RESTITUCION DE TIERRAS Y JUECES CIVILES DEL CIRCUITO ESPECIALIZADOS EN \u00a0 RESTITUCION DE TIERRAS-Naturaleza y marco jur\u00eddico \u00a0 \u00a0<\/p>\n<p>MAGISTRADOS ESPECIALIZADOS EN \u00a0 RESTITUCION DE TIERRAS Y JUECES CIVILES DEL CIRCUITO ESPECILIZADOS EN \u00a0 RESTITUCION DE TIERRAS-Cargos son de carrera y deber\u00e1n ser nombrados por \u00a0 concurso p\u00fablico \u00a0 \u00a0<\/p>\n<p>PROVISION DE CARGOS DE JUECES DE \u00a0 RESTITUCION DE TIERRAS-Conforme al r\u00e9gimen aplicable a la provisi\u00f3n de \u00a0 funcionarios de la Rama Judicial \u00a0 \u00a0<\/p>\n<p>Para la Corte es claro que \u00a0 los cargos de Magistrados y jueces,\u00a0especializados en restituci\u00f3n de tierras: \u00a0 (i) pertenecen a la jurisdicci\u00f3n ordinaria civil; (ii) tienen vocaci\u00f3n de \u00a0 permanencia; (iii) son de carrera, es decir, que deben proveerse mediante un \u00a0 concurso de m\u00e9ritos; de ah\u00ed que, (iv) su nombramiento debe hacerse en propiedad \u00a0 de la lista de elegibles vigente, tal y como, lo consider\u00f3 la Sala \u00a0 Administrativa del Consejo Superior de la Judicatura. \u00a0 \u00a0<\/p>\n<p>DEFECTO MATERIAL O SUSTANTIVO EN ACTUACIONES ADMINISTRATIVAS-Reiteraci\u00f3n de jurisprudencia \u00a0 \u00a0<\/p>\n<p>Resulta pertinente aplicar de manera anal\u00f3gica la categor\u00eda del \u00a0 defecto material o sustantivo, propia del an\u00e1lisis que se hace en los casos de \u00a0 tutela contra providencia judicial, al \u00e1mbito de las actuaciones \u00a0 administrativas, con el fin de verificar si existi\u00f3 la violaci\u00f3n del derecho al \u00a0 debido proceso administrativo de los accionantes. El defecto sustancial o \u00a0 material se presenta cuando la autoridad administrativa aplica una norma \u00a0 claramente inaplicable al caso concreto o, visto desde otra perspectiva, cuando \u00a0 deja de aplicar la que evidentemente lo es. \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA FRENTE A ACTOS ADMINISTRATIVOS EN MATERIA DE CONCURSO DE \u00a0 MERITOS-Procedencia por defecto sustantivo, por cuanto Corte \u00a0 Suprema dej\u00f3 de aplicar los actos administrativos de la Sala Administrativa del \u00a0 Consejo Superior que determinaron que la provisi\u00f3n de cargos de Magistrados \u00a0 Especializados en Restituci\u00f3n de Tierras, se deb\u00eda realizar en propiedad, de la \u00a0 lista de elegibles \u00a0 \u00a0<\/p>\n<p>Se vulner\u00f3 el derecho al debido proceso administrativo de \u00a0 los tutelantes y de los terceros vinculados, por la configuraci\u00f3n de un defecto \u00a0 material o sustantivo. (i) Trat\u00e1ndose de un cargo judicial de carrera, la autoridad nominadora \u00a0 debe aplicar las normas constitucionales, estatutarias y dem\u00e1s normas legales o \u00a0 reglamentarias jur\u00eddicas que disponen su creaci\u00f3n y naturaleza. (ii) La omisi\u00f3n \u00a0 injustificada de designar en propiedad en un cargo de carrera judicial, de \u00a0 car\u00e1cter permanente, a una persona, que aprob\u00f3 el respectivo concurso de m\u00e9ritos \u00a0 y que fue incluida en la lista de elegibles, la hace incursa en un defecto \u00a0 material o sustantivo que vulnera el derecho fundamental al debido proceso \u00a0 administrativo. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Referencia: Expediente T-4.789.181 \u00a0 \u00a0<\/p>\n<p>Fallos de tutela objeto revisi\u00f3n: Sentencia de la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia, del 19 de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0noviembre de 2014, que confirm\u00f3 la\u00a0 Sentencia de la Sala de Casaci\u00f3n \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Civil de la Corte Suprema de Justicia, del 18 de septiembre de 2014. \u00a0 \u00a0<\/p>\n<p>Accionantes: Vicente Landinez Lara, Juan Pablo \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Su\u00e1rez Orozco y Javier Enrique Castillo Cadena. \u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>Accionado: Sala Plena de la Corte Suprema de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Justicia. \u00a0 \u00a0<\/p>\n<p>Magistrado Ponente: MAURICIO GONZ\u00c1LEZ CUERVO. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>I. \u00a0 ANTECEDENTES \u00a0 \u00a0<\/p>\n<p>1.\u00a0\u00a0\u00a0 Demanda de tutela. \u00a0 \u00a0<\/p>\n<p>1.1. Elementos de la demanda. \u00a0 \u00a0<\/p>\n<p>1.1.1. Derechos fundamentales \u00a0 invocados. Trabajo, igualdad de oportunidades, acceder al desempe\u00f1o de \u00a0 funciones y cargos p\u00fablicos, debido proceso administrativo y principio de \u00a0 confianza leg\u00edtima. \u00a0 \u00a0<\/p>\n<p>1.1.2. Conducta que causa la \u00a0 vulneraci\u00f3n. Los actos administrativos proferidos, el primero de ellos, en \u00a0 sesi\u00f3n del 8 de agosto de 2013, comunicado el 12 de agosto del mismo a\u00f1o y, el \u00a0 segundo, en sesi\u00f3n del 5 de septiembre del 2013, comunicado el 18 de septiembre \u00a0 del mismo a\u00f1o, mediante las cuales la Sala Plena de la Corte Suprema de Justicia \u00a0 neg\u00f3 la solicitud de reconsideraci\u00f3n y, rechaz\u00f3 el recurso de reposici\u00f3n, que \u00a0 fueron presentados por los accionantes para obtener el nombramiento en \u00a0 propiedad, en los cargos de Magistrados Sala Civil, especializados en \u00a0 restituci\u00f3n de tierras, del Tribunal Superior de Distrito Judicial de Antioquia. \u00a0 \u00a0<\/p>\n<p>1.1.3. Pretensi\u00f3n. Ordenar a la \u00a0 accionada que nombre, en propiedad, a los accionantes en el cargo referido. \u00a0 \u00a0<\/p>\n<p>1.2. Fundamentos de la pretensi\u00f3n. \u00a0 \u00a0<\/p>\n<p>1.2.2. Por lo anterior, la misma Sala Administrativa del \u00a0 C.S.J., mediante sendos acuerdos[2] \u00a0formul\u00f3 ante la Corte Suprema de Justicia las listas de candidatos tomadas del \u00a0 Registro Nacional de Elegibles vigente, integrado por las personas que aprobaron \u00a0 el concurso de m\u00e9ritos convocado mediante Acuerdo No.4528 de 2008, destinadas \u00a0 exclusivamente a proveer las tres (3) vacantes del cargo de Magistrado del \u00a0 Tribunal Superior, Sala Civil, de los distritos judiciales referidos. \u00a0 \u00a0<\/p>\n<p>1.2.3. La Sala Plena de la \u00a0 Corte Suprema de Justicia, en sesi\u00f3n ordinaria del 10 de mayo de 2012 nombr\u00f3, en \u00a0 provisionalidad, a los accionantes en los cargos de Magistrados de Sala Civil, \u00a0 especializados en restituci\u00f3n de tierras, en el Tribunal Superior de Distrito \u00a0 Judicial de Antioquia y solicit\u00f3 a la Sala Administrativa del C.S.J. que \u00a0 convocara un concurso de m\u00e9ritos espec\u00edfico para la especialidad. Bajo esta \u00a0 misma modalidad, nombr\u00f3 a los magistrados de dicha especialidad, en los otros \u00a0 distritos judiciales. \u00a0 \u00a0<\/p>\n<p>En el acta n\u00famero 19 de la \u00a0 sesi\u00f3n mencionada, se dej\u00f3 constancia de que el Acuerdo que cre\u00f3 los cargos \u201cno \u00a0 especific\u00f3 si eran de carrera o si se creaban en provisionalidad, dado que la \u00a0 Ley 1448 de 2011 tiene una vigencia de 10 a\u00f1os (\u2026)\u201d; asimismo que, \u201cla \u00a0 Sala de Gobierno de la Corte, decidi\u00f3 que previamente a efectuar los \u00a0 nombramientos, se solicitara a la Sala Administrativa la aclaraci\u00f3n del car\u00e1cter \u00a0 de dichos cargos, el cual fue respondido remitiendo un concepto impreciso y \u00a0 equ\u00edvoco de la Unidad de Carrera Judicial, que se\u00f1ala que son de car\u00e1cter \u00a0 permanente.\u201d Por tal raz\u00f3n, el alto tribunal resolvi\u00f3 que \u201cdichos nombramientos deb\u00edan serlo en provisionalidad, por la \u00a0 temporalidad de la Ley 1448 de 2011, tal como ocurre con la Ley de Justicia y \u00a0 Paz\u201d[3]. \u00a0 \u00a0<\/p>\n<p>1.2.4. El 20 de mayo de 2013, los magistrados de restituci\u00f3n \u00a0 de tierras nombrados en provisionalidad, incluidos los actores, presentaron \u00a0 derecho de petici\u00f3n ante la Presidenta de la Sala Civil de la Corte Suprema de \u00a0 Justicia, para que por su intermedio, propusiera a la Sala Plena de dicha \u00a0 Corporaci\u00f3n la reconsideraci\u00f3n de la decisi\u00f3n adoptada en la sesi\u00f3n ordinaria \u00a0 del 10 de mayo de 2012, y en tal sentido, los nombrara en propiedad en el cargo \u00a0 mencionado[4]. En s\u00edntesis, \u00a0 los fundamentos f\u00e1cticos y jur\u00eddicos de la petici\u00f3n fueron los siguientes: \u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>&#8211; Se\u00f1alaron que el art\u00edculo 119 de \u00a0 la Ley 1448 de 2011, orden\u00f3 la creaci\u00f3n de los cargos de Magistrados de Sala \u00a0 Civil, especializados en restituci\u00f3n de tierras, de conformidad con el numeral \u00a0 5\u00ba del art\u00edculo 85 de la Ley 270 de 1996, norma que faculta a la Sala \u00a0 Administrativa del C.S.J. para crear cargos de naturaleza permanente, y no con \u00a0 base en lo previsto en el art\u00edculo 63 de dicha ley, que en su literal d), le \u00a0 permite cr\u00e9alos \u201ccon car\u00e1cter transitorio\u201d. \u00a0 \u00a0<\/p>\n<p>&#8211; Adujeron que en algunos de los \u00a0 debates legislativos sobre el proyecto de la Ley 1448 de 2011, el Congreso \u00a0 consider\u00f3, en un primer momento, darle el car\u00e1cter de temporales a los cargos de \u00a0 los magistrados especializados en restituci\u00f3n de tierras, y as\u00ed se present\u00f3 el \u00a0 art\u00edculo respectivo. Pero finalmente, la transitoriedad de los cargos en \u00a0 comento, fue eliminada del texto definitivo de la norma promulgada, que en su \u00a0 art\u00edculo 79, da permanencia a dichos cargos. \u00a0 \u00a0<\/p>\n<p>&#8211; Afirmaron que la naturaleza de \u00a0 sus cargos es totalmente diferente a la de los Magistrados de Justicia y Paz, en \u00a0 tanto la Ley 975 de 2005, en su art\u00edculo 67, dispuso que su provisi\u00f3n no se \u00a0 har\u00eda por concurso. Adem\u00e1s que, dicha ley no asign\u00f3 tales cargos a una sala \u00a0 determinada, como s\u00ed lo hizo el art\u00edculo 79 de la Ley 1448 de 2011, con los \u00a0 Magistrados Sala Civil, especializados a la restituci\u00f3n de tierras. \u00a0 \u00a0<\/p>\n<p>&#8211; Indicaron que la Sala \u00a0 Administrativa del C.S.J., mediante el Acuerdo PSAA13-9866 del 13 de marzo de \u00a0 2013, determin\u00f3 que los cargos referidos hacen parte de la jurisdicci\u00f3n \u00a0 ordinaria civil, pues hacen parte de la Sala Civil del respectivo Tribunal \u00a0 Superior de Distrito Judicial (art\u00edculo 1\u00ba). En ese sentido, se\u00f1alaron que dicha \u00a0 Sala Administrativa, en sesi\u00f3n de 23 de agosto de 2012, aprob\u00f3 los conceptos \u00a0 proferidos por la Unidad de Carrera Judicial, en el sentido de que los cargos en \u00a0 cuesti\u00f3n son permanentes y de carrera, por lo que deben proveerse en propiedad. \u00a0 \u00a0<\/p>\n<p>&#8211; Aseveraron que por las anteriores \u00a0 razones, fueron nombrados en propiedad de los Registros de Elegibles vigente, \u00a0 algunos de los jueces civiles especializados en restituci\u00f3n de tierras.\u00a0 \u00a0 \u00a0<\/p>\n<p>1.2.4.1. El 31 de mayo de 2013, los peticionarios remitieron \u00a0 a la Sala Civil de la Corte Suprema, como complemento de la anterior petici\u00f3n, \u00a0 copia de la Circular PSAC-13-14 del 27 de mayo de 2013, expedida por la Sala \u00a0 Administrativa del Consejo Superior de la Judicatura. En dicha circular se \u00a0 establece que los cargos de jueces, magistrados, empleados, creados en virtud de \u00a0 la Ley 1448 de 2011, \u201cdeben ser provistos en propiedad de los Registros de \u00a0 Elegibles vigentes y en ese sentido, corresponde a la autoridad nominadora \u00a0 proveerlos en la forma indicada\u201d[5].\u00a0 \u00a0 \u00a0<\/p>\n<p>1.2.5. Mediante oficios PCSJ No.1382, 1384, 1385 del 12 de \u00a0 agosto de 2013, recibidos el 20 de agosto del mismo a\u00f1o, la Presidenta de la \u00a0 Corte Suprema de Justicia les inform\u00f3 a los peticionarios que, en sesi\u00f3n \u00a0 plenaria del 8 de agosto de 2013, se resolvi\u00f3 negar su solicitud[6].\u00a0 \u00a0 \u00a0<\/p>\n<p>1.2.6. El 26 de agosto de 2013, presentaron recurso de \u00a0 reposici\u00f3n contra los \u201cactos administrativos\u201d que negaron la petici\u00f3n del \u00a0 20 de mayo del mismo a\u00f1o y, contra la decisi\u00f3n tomada en la sesi\u00f3n plenaria del \u00a0 8 de agosto de 2013, por desconocer los fundamentos que dieron lugar a la \u00a0 negativa de lo pedido. Sin embargo, la Corporaci\u00f3n accionada, mediante oficios \u00a0 OSG No.5677, 5678 y 5679 del 18 de septiembre de 2013[7], comunic\u00f3 la decisi\u00f3n \u00a0 adoptada en sesi\u00f3n ordinaria del 5 de septiembre del mismo a\u00f1o, en el sentido de \u00a0 rechazar por improcedente dicho recurso, por considerar que los peticionarios no \u00a0 interpusieron los recursos de ley establecidos contra los actos de nombramiento \u00a0 y confirmaci\u00f3n[8].\u00a0 \u00a0 \u00a0<\/p>\n<p>1.2.7. Con fundamento \u00a0 en lo anterior, los se\u00f1ores Vicente Landinez Lara, Juan Pablo Su\u00e1rez Orozco y \u00a0 Javier Enrique Castillo Cadena, presentaron acci\u00f3n de tutela contra la Sala \u00a0 Plena de la Corte Suprema de Justicia, en los siguientes t\u00e9rminos: \u00a0 \u00a0<\/p>\n<p>En primer lugar, \u00a0 se\u00f1alaron que la jurisprudencia constitucional[9], \u00a0 ha establecido que la acci\u00f3n de tutela es el mecanismo id\u00f3neo y eficaz con el \u00a0 que cuenta una persona para controvertir la negativa a proveer cargos de \u00a0 carrera, de conformidad con los resultados publicados en la listas de elegibles \u00a0 por los concursos de m\u00e9rito. En el caso concreto, alegaron que este era el \u00fanico \u00a0 mecanismo eficaz con el que contaban, para que los jueces estudiaran los \u00a0 fundamentos de los actos de nombramiento, los cuales consideran han deca\u00eddo por \u00a0 causa de un hecho nuevo, que consiste en el Acuerdo y la Circular \u00a0 expedida por la Sala Administrativa del Consejo Superior de la Judicatura. \u00a0 \u00a0<\/p>\n<p>En segundo lugar, \u00a0 manifestaron que, la acci\u00f3n de tutela satisface el requisito de inmediatez, por \u00a0 cuanto los actos que sirvieron de fundamento a la demanda de tutela, y que \u00a0 resolvieron la discrepancia de conceptos sobre el tipo de nombramiento (en \u00a0 provisionalidad o en propiedad), fueron dictados por la Sala Administrativa con \u00a0 posterioridad a los actos de nombramiento (mayo 2012), es decir, en mayo de \u00a0 2013. \u00a0 \u00a0<\/p>\n<p>En tercer lugar, \u00a0 alegaron que fueron vulnerados sus derechos fundamentales, porque la accionada \u00a0 mantiene sus nombramientos en provisionalidad, cuando el mismo debi\u00f3 efectuarse \u00a0 en propiedad, por cuanto superaron el concurso de m\u00e9ritos convocado en el a\u00f1o \u00a0 2008 y, por ende, pasaron a hacer parte de la lista de elegibles que fue \u00a0 formulada por la Sala Administrativa del C.S.J. a la entidad accionada. \u00a0 \u00a0<\/p>\n<p>En ese orden, \u00a0 aseveraron que: (i) se vulner\u00f3 el derecho a la igualdad de oportunidades, debido \u00a0 a que los jueces y dem\u00e1s empleados de restituci\u00f3n de tierras han sido nombrados \u00a0 en propiedad, contrario a lo est\u00e1 sucediendo con los magistrados de la misma \u00a0 especialidad; (ii) se vulner\u00f3 el derecho al trabajo y el derecho de desempe\u00f1ar \u00a0 cargos y funciones p\u00fablicas, porque se omiti\u00f3 el contenido del art\u00edculo 25 y 40, \u00a0 numeral 7, de la Carta Pol\u00edtica; y (iii) se vulner\u00f3 el derecho al debido proceso \u00a0 administrativo y, se desconoci\u00f3 el principio de confianza leg\u00edtima, toda vez \u00a0 que, la accionada solicit\u00f3 a la Sala Administrativa que convocara a un nuevo \u00a0 concurso para la especialidad de restituci\u00f3n de tierras, a pesar de que hay una \u00a0 lista de elegibles vigente, agregando de esta forma etapas y requisitos \u00a0 adicionales a un tr\u00e1mite administrativo ya surtido. En ese sentido, afirm\u00f3 que \u00a0 la prueba de que no se necesitaba de un nuevo concurso es que en la reciente \u00a0 convocatoria a concurso de m\u00e9ritos para proveer cargos de la Rama Judicial \u00a0 (Acuerdo No.PSAA13-9939 de 2013), no se incluy\u00f3 el cargo de Magistrado \u00a0 especializado en restituci\u00f3n de tierras, sino el de \u201cMagistrado de Tribunal \u00a0 Superior \u2013Sala Civil\u201d, de cuyo registro se proveer\u00e1n aquellos[10]. \u00a0 \u00a0<\/p>\n<p>Finalmente, alegaron \u00a0 que la vulneraci\u00f3n permanece en el tiempo porque contin\u00faan nombrados en \u00a0 provisionalidad en cargos que son de car\u00e1cter permanente. Circunstancia que, a \u00a0 su juicio, da actualidad y firmeza a la configuraci\u00f3n del perjuicio.\u00a0 \u00a0 \u00a0<\/p>\n<p>2. Respuesta de la autoridad accionada y de los terceros \u00a0 vinculados[11]. \u00a0 \u00a0<\/p>\n<p>2.1. La Sala Plena de la Corte Suprema de Justicia. \u00a0 Solicit\u00f3 que se denegara el amparo reclamado por los accionantes. Ello, por \u00a0 cuanto, en cumplimiento de lo dispuesto en el acuerdo que cre\u00f3 los cargos de \u00a0 Magistrados, especializados en restituci\u00f3n de tierras, design\u00f3 a las personas \u00a0 que ocupar\u00edan, en provisionalidad, dichas plazas. Resalt\u00f3 que si los actores no \u00a0 compart\u00edan la forma como en la sesi\u00f3n del 10 de mayo de 2012 se nombraron los \u00a0 cargos en cuesti\u00f3n, sus reparos han debido manifestarlos en la oportunidad \u00a0 legal, contra los actos de nombramiento y confirmaci\u00f3n, como se les hizo saber \u00a0 en la providencia del 5 de septiembre de 2013. De este modo, concluy\u00f3 que la \u00a0 controversia planteada por los actores desborda las potestades del juez \u00a0 constitucional. \u00a0 \u00a0<\/p>\n<p>2.2. Unidad de Administraci\u00f3n de la Carrera Judicial del \u00a0 Consejo Superior de la Judicatura. Solicit\u00f3 que se negara la acci\u00f3n de \u00a0 tutela, porque existe un mecanismo de defensa ordinario para controvertir la \u00a0 legalidad de los actos administrativos de nombramiento, adem\u00e1s que, no se cumple \u00a0 con el requisito de inmediatez[12]. \u00a0 \u00a0<\/p>\n<p>2.3. Secretar\u00eda General de la Corte Suprema de Justicia. \u00a0Alleg\u00f3 un informe en el que hace una rese\u00f1a sobre el tr\u00e1mite surtido por dicha \u00a0 Corporaci\u00f3n, en el procedimiento de nombramiento de los Magistrados de las Salas \u00a0 Civiles, especializados en restituci\u00f3n de tierras[13]. \u00a0 \u00a0<\/p>\n<p>2.4. Puno Alirio Correal Beltr\u00e1n. Solicit\u00f3 remitir las \u00a0 diligencias por competencia al Tribunal Contencioso Administrativo de \u00a0 Cundinamarca, porque la acci\u00f3n de tutela se dirige contra una autoridad del \u00a0 orden nacional por un acto donde ejerc\u00eda funci\u00f3n p\u00fablica administrativa y no \u00a0 judicial, a quien reclam\u00f3 la protecci\u00f3n de sus derechos fundamentales a la \u00a0 igualdad y al debido proceso, en virtud de que fue elegido por la accionada en \u00a0 la sesi\u00f3n del 10 de mayo de 2012 como magistrado de Sala Civil de Tribunal en \u00a0 provisionalidad, cuando lo que correspond\u00eda era en propiedad[14]. \u00a0 \u00a0<\/p>\n<p>2.5. Gloria del Socorro Victoria Giraldo. Solicit\u00f3 que \u00a0 se hiciera extensivo los efectos favorables del amparo implorado, a los derechos \u00a0 de los que es titular y, que se han visto vulnerados con la actuaci\u00f3n de la \u00a0 accionada, al haberla nombrado en provisionalidad en el cargo referido, en el \u00a0 distrito judicial de Cali. Se\u00f1al\u00f3 que en la Sentencia T-319 de 2014, la Corte \u00a0 Constitucional ya se hab\u00eda pronunciado respecto de esta problem\u00e1tica[15]. \u00a0 \u00a0<\/p>\n<p>2.6. Martha Patricia Campo Valero y Ada Patricia \u00a0 Llallemand Abramuck. Reclamaron el amparo de los derechos fundamentales \u00a0 invocados en el l\u00edbelo introductor, por haber sido vulnerados por la autoridad \u00a0 judicial accionada. Por lo anterior, insistieron en la pretensi\u00f3n principal \u00a0 planteada en la tutela, es decir, que se ordene hacer el nombramiento en \u00a0 propiedad. De igual forma, sostuvieron que en la Sentencia T-319 de 2014 se \u00a0 zanj\u00f3 la disparidad de interpretaciones, suscitada en torno a la designaci\u00f3n en \u00a0 propiedad o provisionalidad de los cargos de Magistrados de restituci\u00f3n de \u00a0 tierras[16]. \u00a0 \u00a0<\/p>\n<p>2.8. Jorge Eliecer Moya Vargas. Reiter\u00f3 los argumentos \u00a0 formulados por los accionantes en la demanda de tutela y, agreg\u00f3 que la \u00a0 autoridad judicial accionada en la sesi\u00f3n del 8 de agosto de 2013, Acta 21, \u00a0 desconoci\u00f3 el Acuerdo del 13 de marzo de 2013 y la Circular del 27 de mayo del \u00a0 mismo a\u00f1o, no obstante ser vinculantes por tratarse de actos administrativos \u00a0 vigentes que gozan presunci\u00f3n de legalidad. Por \u00faltimo, hizo referencia a la \u00a0 Sentencia T-319 de 2014[18]. \u00a0 \u00a0<\/p>\n<p>2.9. Amanda Janeth S\u00e1nchez Tocora. Manifest\u00f3 que \u00a0 coadyuva la solicitud de amparo elevada por los accionantes y que se adhiere a \u00a0 los fundamentos f\u00e1cticos y jur\u00eddicos de la misma[19]. \u00a0 \u00a0<\/p>\n<p>2.10. Nelson Yesid Ru\u00edz Hern\u00e1ndez. Adujo que se \u00a0 encuentra en exactas condiciones a las de los iniciales demandantes, por ello, \u00a0 solicit\u00f3 que fuera tenido en cuenta como coaccionante y, que se extendieran a su \u00a0 favor los efectos del fallo de tutela[20]. \u00a0 \u00a0<\/p>\n<p>3. \u00a0 Decisiones judiciales objeto de revisi\u00f3n[21]. \u00a0 \u00a0<\/p>\n<p>3.1. Sentencia de la Sala de Casaci\u00f3n Civil de la Corte \u00a0 Suprema de Justicia, del 18 de septiembre de 2014. La Sala de conjueces \u00a0 deneg\u00f3 la protecci\u00f3n constitucional invocada. \u00a0 \u00a0<\/p>\n<p>En primer t\u00e9rmino, se\u00f1al\u00f3 que los actores, mediante oficio \u00a0 del 10 de septiembre de 2014, adicionaron la demanda de tutela, aduciendo que la \u00a0 Sentencia T-319 de 2014 de la Corte Constitucional, zanj\u00f3 la disparidad de \u00a0 interpretaciones suscitada en torno a la designaci\u00f3n en propiedad o en \u00a0 provisionalidad de los cargos de Magistrados de la Sala Civil, especializada en \u00a0 restituci\u00f3n de tierras. En efecto, precis\u00f3 que dichos cargos son de car\u00e1cter \u00a0 permanente \u2013de carrera-, pertenecientes a la jurisdicci\u00f3n civil, y por tanto, la \u00a0 provisi\u00f3n de los mismos deben ser en propiedad. \u00a0 \u00a0<\/p>\n<p>En segundo t\u00e9rmino, manifest\u00f3 que si bien es cierto, la Sala \u00a0 Administrativa indic\u00f3 que los cargos eran de car\u00e1cter permanente, ello no \u00a0 significa que su nombramiento ten\u00eda que ser de carrera, pues no existe un \u00a0 concurso de m\u00e9ritos para la provisi\u00f3n de esos cargos espec\u00edficos, motivo por el \u00a0 cual no puede hacerse los mentados nombramientos en propiedad. Los accionantes y \u00a0 terceros vinculados al momento de su nombramiento conoc\u00edan que hab\u00edan sido \u00a0 nombrados en provisionalidad, sin que en su momento oportuno interpusieran los \u00a0 recursos y las acciones contenciosas establecidas en la ley para presentar su \u00a0 inconformidad. Adem\u00e1s, se\u00f1al\u00f3 que la acci\u00f3n de tutela no tiene lugar cuando no \u00a0 existe un perjuicio irremediable, como ocurre en el presente caso, puesto que, \u00a0 los nombrados se han desempe\u00f1ado normalmente en sus cargos desde el mismo \u00a0 momento de sus nombramientos, sin que con ello se les haya causado perjuicio \u00a0 alguno, por el contrario se han venido beneficiando por todas las prebendas que \u00a0 el cargo les ha ofrecido. \u00a0 \u00a0<\/p>\n<p>En tercer t\u00e9rmino, concluy\u00f3 que no procede la acci\u00f3n de \u00a0 tutela por incumplir con el requisito de inmediatez, en tanto dej\u00f3 transcurrir \u00a0 un tiempo prolongado entre la interposici\u00f3n de la acci\u00f3n constitucional y el \u00a0 hecho que presuntamente gener\u00f3 la vulneraci\u00f3n, acaecido el 10 de mayo de 2012, \u00a0 fecha del nombramiento.\u00a0 \u00a0 \u00a0<\/p>\n<p>Por \u00faltimo, se\u00f1al\u00f3 que no era del caso, aplicar lo dispuesto \u00a0 en la Sentencia T-319 de 2014 por ser diferentes las circunstancias y por \u00a0 consiguiente no recibe los efectos inter comunis all\u00ed mencionados. \u00a0 \u00a0<\/p>\n<p>3.2. Impugnaci\u00f3n[22]. \u00a0El se\u00f1or Jorge Eliecer Moya aleg\u00f3 que su intervenci\u00f3n en la acci\u00f3n de tutela \u00a0 no fue tenida en cuenta para adoptar la decisi\u00f3n, ni siquiera se menciona en el \u00a0 fallo. En oposici\u00f3n al fallo del a quo, se\u00f1al\u00f3 que el per\u00edodo de \u00a0 inactividad para el ejercicio de la acci\u00f3n de tutela est\u00e1 plenamente \u00a0 justificado, pues solo acaeci\u00f3 mientras el Consejo Superior de la Judicatura en \u00a0 su calidad de responsable de administrar la carrera judicial, efectu\u00f3 el \u00a0 pronunciamiento definitivo (Acuerdo y Circular de mayo de 2013) que zanjara la \u00a0 discrepancia conceptual con la Corte Suprema de Justicia. En todo caso, precis\u00f3 \u00a0 que de existir tardanza en la interposici\u00f3n de la acci\u00f3n de tutela, lo cierto es \u00a0 que hay situaciones que lo justifican, tales como, (i) la vulneraci\u00f3n permanente \u00a0 de sus derechos fundamentales, por mantenerse su nombramiento en \u00a0 provisionalidad, y (ii) la ocurrencia de un hecho nuevo, cual es, la expedici\u00f3n \u00a0 de los Acuerdos y la Circular por parte de la Sala Administrativa del C.S.J. \u00a0 Finalmente, resalt\u00f3 que en la Sentencia T-319 de 2014, se hizo una salvedad en \u00a0 el sentido de que el juez de tutela podr\u00eda llegar a soluciones distintas, por \u00a0 ejemplo, cuando el servidor\u00a0 es promovido a un cargo de restituci\u00f3n de \u00a0 tierras y luego de finalizada su vigencia pierde el derecho a la carrera \u00a0 judicial o se ve obligado a renunciar a esta. \u00a0 \u00a0<\/p>\n<p>3.3 Sentencia de la Sala de Casaci\u00f3n Laboral de la Corte \u00a0 Suprema de Justicia, Sala de Casaci\u00f3n Laboral, del 19 de noviembre de 2014. \u00a0 La Sala de conjueces resolvi\u00f3 confirmar el fallo de primera instancia, por las \u00a0 siguientes razones: (i) el impugnante fue vinculado como tercero con inter\u00e9s en \u00a0 el proceso de tutela (D. 2591\/91, art. 13, inciso 2) y, por tanto, est\u00e1 \u00a0 legitimado para impugnar el fallo de primera instancia; (ii) ante la ausencia \u00a0 injustificada de activaci\u00f3n del mecanismo judicial respectivo, la acci\u00f3n de \u00a0 tutela deviene improcedente. Adem\u00e1s que, el amparo no est\u00e1 llamado a prosperar \u00a0 ni siquiera de manera transitoria, porque no existe prueba de un perjuicio \u00a0 irremediable; (iii) la interposici\u00f3n de la acci\u00f3n constitucional fue \u00a0 extempor\u00e1nea; (iv) la interpretaci\u00f3n de la autoridad accionada no es arbitraria \u00a0 o caprichosa, pues en el acta de 10 de mayo de 2012 se evidencia las razones que \u00a0 sustentaron la decisi\u00f3n; y por \u00faltimo, (v) la Sentencia T-319 de 2014 no declar\u00f3 \u00a0 los efectos inter comunis. \u00a0 \u00a0<\/p>\n<p>4. Solicitud de insistencia. \u00a0 \u00a0<\/p>\n<p>Mediante escrito del 13 de abril de 2015, la H. Magistrada \u00a0 Martha Victoria S\u00e1chica M\u00e9ndez present\u00f3 solicitud de insistencia ante la Sala de \u00a0 Selecci\u00f3n No.4 de esta Corporaci\u00f3n, con el fin de que fuera seleccionado el \u00a0 proceso bajo estudio. En el escrito de insistencia se exponen las siguientes \u00a0 razones para la selecci\u00f3n del caso: (i) reiterar la jurisprudencia respecto de \u00a0 la naturaleza de los cargos de servidores judiciales de restituci\u00f3n de tierras; \u00a0 (ii) reafirmar el precedente relacionado con que la carrera administrativa es la \u00a0 regla general en la provisi\u00f3n de cargos p\u00fablicos; (iii) unificar jurisprudencia \u00a0 respecto del nombramiento de los cargos de jueces y magistrados de restituci\u00f3n \u00a0 de tierras; (iv) verificar si en el caso concreto se cumplen los requisitos de \u00a0 subsidiariedad e inmediatez; y (v) determinar si, de acuerdo con la Sentencias \u00a0 T-319 de 2014; C-333 de 2012 y C-532 de 2013, los cargos de restituci\u00f3n de \u00a0 tierras son de car\u00e1cter permanente, o s\u00ed por el contrario, est\u00e1n circunscritos \u00a0 al marco del conflicto[23]. \u00a0 \u00a0<\/p>\n<p>II. CONSIDERACIONES. \u00a0 \u00a0<\/p>\n<p>1. Competencia. \u00a0 \u00a0<\/p>\n<p>La Corte Constitucional es competente para revisar las \u00a0 decisiones judiciales mencionadas, con base en la Constituci\u00f3n Pol\u00edtica \u00a0 -art\u00edculos 86 y 241.9- y lo desarrollado en el Decreto 2591 de 1991 -art\u00edculos \u00a0 31 a 36[24]. \u00a0 \u00a0<\/p>\n<p>2. Procedencia de la demanda de tutela[25]. \u00a0 \u00a0<\/p>\n<p>2.1. Alegaci\u00f3n de \u00a0 afectaci\u00f3n de un derecho fundamental. En el \u00a0 caso bajo estudio se analiza la posible vulneraci\u00f3n al trabajo, a la \u00a0 igualdad de oportunidades, al derecho a acceder al desempe\u00f1o de funciones y \u00a0 cargos p\u00fablicos y, al debido proceso administrativo. \u00a0 \u00a0<\/p>\n<p>2.2. Legitimaci\u00f3n activa. Los accionantes en calidad de titulares de los derechos \u00a0 presuntamente vulnerados interpusieron la acci\u00f3n de tutela de manera directa \u00a0 (C.P. art. 86\u00ba, D. 2591\/91 art. 1\u00ba y art.10\u00b0).\u00a0 \u00a0 \u00a0<\/p>\n<p>2.3. Legitimaci\u00f3n pasiva. La Corte Suprema de Justicia \u00a0 -Sala Plena- es una entidad de naturaleza p\u00fablica, por tanto, la solicitud de \u00a0 amparo es procedente. (C.P. 86\u00b0, D. 2591\/91 art. 1\u00b0 y art. 13\u00b0). \u00a0 \u00a0<\/p>\n<p>2.4. Inmediatez.\u00a0 \u00a0 \u00a0<\/p>\n<p>2.4.1. Jurisprudencia. Reiteraci\u00f3n. \u00a0 \u00a0<\/p>\n<p>2.4.1.1. En reiterada jurisprudencia[26] \u00a0este Tribunal Constitucional ha insistido en que, si bien el art\u00edculo 86 de la \u00a0 Constituci\u00f3n Pol\u00edtica, se\u00f1ala que la acci\u00f3n de tutela puede ser interpuesta \u00a0 \u201cen todo momento\u201d, ello no significa que no deba interponerse en un plazo \u00a0 razonable desde el inicio de la amenaza o vulneraci\u00f3n pues, de acuerdo con el \u00a0 mismo art\u00edculo constitucional, es un mecanismo dise\u00f1ado para reclamar \u201cla \u00a0 protecci\u00f3n inmediata\u201d de los derechos fundamentales[27]. De ah\u00ed que, le \u00a0 corresponda al juez constitucional tomar en cuenta como dato relevante, el \u00a0 tiempo transcurrido entre el hecho generador de la solicitud y la petici\u00f3n de \u00a0 amparo, pues un lapso irrazonable puede llegar a demostrar que la soluci\u00f3n que \u00a0 se reclama no se requiere con prontitud, como se espera en los casos para las \u00a0 cuales el mecanismo preferente y sumario de la tutela est\u00e1 reservado[28].[29] \u00a0 \u00a0<\/p>\n<p>2.4.1.2. Para \u00a0 tal efecto, la jurisprudencia constitucional ha se\u00f1alado algunos criterios \u00a0 generales para orientar al juez de tutela en el momento que deba establecer la \u00a0 razonabilidad y oportunidad de la interposici\u00f3n de la acci\u00f3n de tutela, a saber: \u00a0 \u00a0<\/p>\n<p>\u00a0\u201c(i) \u00a0 si existe un motivo v\u00e1lido para la inactividad de los accionantes; (ii) si la \u00a0 inactividad justificada vulnera el n\u00facleo esencial de los derechos de terceros \u00a0 afectados con la decisi\u00f3n; (iii) si existe un nexo causal entre el ejercicio \u00a0 tard\u00edo de la acci\u00f3n y la vulneraci\u00f3n de los derechos fundamentales del \u00a0 interesado;[30] (iv) si el \u00a0 fundamento de la acci\u00f3n de tutela surgi\u00f3 despu\u00e9s de acaecida la actuaci\u00f3n \u00a0 violatoria de los derechos fundamentales, de cualquier forma en un plazo no muy \u00a0 alejado de la fecha de interposici\u00f3n.\u201d[31] \u00a0 \u00a0<\/p>\n<p>2.4.1.3. Asimismo, se \u00a0 han indicado los dos \u00fanicos casos en los que no es exigible el principio de \u00a0 inmediatez de modo estricto: (i)\u00a0cuando\u00a0 se demuestre que la vulneraci\u00f3n es \u00a0 permanente en el tiempo y que, pese a que el hecho que la origin\u00f3 por primera \u00a0 vez es muy antiguo respecto de la presentaci\u00f3n de la tutela, la situaci\u00f3n es \u00a0 continua y actual; y (ii)\u00a0cuando la especial situaci\u00f3n de aquella persona a \u00a0 quien se le han vulnerado sus derechos fundamentales, hace desproporcionado el \u00a0 hecho de adjudicarle la carga de acudir a un juez; por ejemplo, el estado de \u00a0 indefensi\u00f3n, interdicci\u00f3n, abandono, minor\u00eda de edad, incapacidad f\u00edsica, entre \u00a0 otros[32]. \u00a0 \u00a0<\/p>\n<p>2.4.1.4. A modo de \u00a0 conclusi\u00f3n, la inmediatez m\u00e1s que un requisito de procedibilidad, constituye un \u00a0 elemento esencial o caracter\u00edstica principal de la acci\u00f3n de tutela. Por tal \u00a0 raz\u00f3n, el examen del mismo no se reduce a \u00a0 verificar simplemente el paso del tiempo entre el hecho generador de la \u00a0 vulneraci\u00f3n de un derecho fundamental y la interposici\u00f3n de la demanda de \u00a0 tutela, sino que, adem\u00e1s comprende la valoraci\u00f3n de la razonabilidad del plazo, \u00a0 la cual est\u00e1 sujeta a los hechos que configuran el caso concreto y debe ser \u00a0 efectuada por el juez de tutela atendiendo a los criterios que sobre el \u00a0 particular ha fijado la jurisprudencia constitucional. \u00a0 \u00a0<\/p>\n<p>2.4.2. Falta de inmediatez, en criterio de la \u00a0 accionada. \u00a0 \u00a0<\/p>\n<p>2.4.2.1. En el presente asunto, los accionantes \u00a0 interpusieron acci\u00f3n de tutela contra la Sala Plena de la Corte Suprema de \u00a0 Justicia, alegando que fueron vulnerados sus derechos fundamentales, por haber \u00a0 sido nombrados, en provisionalidad, en los cargos de Magistrados de Tribunal \u00a0 Superior, Sala Civil, especialidad de restituci\u00f3n de tierras, cuando a su \u00a0 parecer tales nombramientos debieron haberse hecho en propiedad. \u00a0 \u00a0<\/p>\n<p>2.4.2.2. Las Salas Civil y \u00a0 Laboral de la Corte Suprema de Justicia, actuando como jueces de tutela, negaron \u00a0 por improcedente el amparo deprecado, por considerar que no se hab\u00eda cumplido \u00a0 con el requisito de inmediatez. En ese sentido, se\u00f1alaron que se dej\u00f3 \u00a0 transcurrir un tiempo prolongado e injustificado entre la interposici\u00f3n de la \u00a0 acci\u00f3n constitucional -24 de octubre de 2013- y el hecho que presuntamente \u00a0 gener\u00f3 la vulneraci\u00f3n, este es, la decisi\u00f3n adoptada en la plenaria celebrada el \u00a0 10 de mayo de 2012, en la que se resolvi\u00f3 nombrar en provisionalidad a los \u00a0 actores. \u00a0 \u00a0<\/p>\n<p>2.4.2.3. La Sala Laboral del tribunal mencionado reforz\u00f3 el \u00a0 anterior argumento al precisar que, en forma alguna pod\u00eda contabilizarse, a \u00a0 partir del rechazo del recurso de reposici\u00f3n, expedido el 5 de septiembre de \u00a0 2013, el t\u00e9rmino de los 6 meses que ha establecido la jurisprudencia de esa \u00a0 Corporaci\u00f3n, como razonable para interponer la acci\u00f3n de tutela. Ello, por \u00a0 cuanto entre la designaci\u00f3n que fue efectuada -10 de mayo de 2012- y la \u00a0 reconsideraci\u00f3n solicitada -20 de mayo de 2013 &#8211; transcurri\u00f3 m\u00e1s de un a\u00f1o, lo \u00a0 que en efecto demuestra que las actuaciones de los actores no han sido \u00a0 concatenadas a la decisi\u00f3n inicialmente adoptada. \u00a0 \u00a0<\/p>\n<p>2.4.3. Examen de inmediatez. \u00a0 \u00a0<\/p>\n<p>Con base en los elementos del caso concreto y atendiendo al reiterado \u00a0 precedente que ha fijado sobre el tema la jurisprudencia constitucional, la \u00a0 Corte proceder\u00e1 a verificar si la acci\u00f3n de tutela cumple o no con el requisito \u00a0 de inmediatez. \u00a0 \u00a0<\/p>\n<p>2.4.3.1. Para tal efecto, es importante recordar que, en un primer \u00a0 momento, ante la falta de certeza respecto de la naturaleza de los cargos de los \u00a0 funcionarios de restituci\u00f3n de tierras, el nominador (la Sala Plena de la Corte \u00a0 Suprema de Justicia) solicit\u00f3 a la Sala Administrativa del C.S.J. aclaraci\u00f3n \u00a0 acerca de este tema, la cual fue respondida mediante un concepto de la Unidad de \u00a0 Administraci\u00f3n de Carrera Judicial en el sentido de que dichas plazas eran de \u00a0 car\u00e1cter permanente. No obstante, el nominador consider\u00f3 dicho concepto, por \u00a0 considerarlo \u201cimpreciso y equ\u00edvoco\u201d, y nombr\u00f3 a los accionantes en \u00a0 provisionalidad, solicitando al Consejo Superior de la Judicatura que convocara \u00a0 a un nuevo concurso de m\u00e9ritos para proveer dichos cargos. \u00a0 \u00a0 \u00a0<\/p>\n<p>2.4.3.2. En un segundo momento, la Sala Administrativa del Consejo \u00a0 Superior de la Judicatura mediante el Acuerdo PSAA13-9866 del 13 \u00a0 de marzo de 2013 y\u00a0 la Circular PSAC13-14 del 27 de mayo del 2013 determin\u00f3 que los \u00a0 cargos referidos eran de naturaleza permanente y que deb\u00edan ser provistos en \u00a0 propiedad. Por tal raz\u00f3n, los accionantes presentaron, el 20 de mayo de 2013, \u00a0 solicitud de reconsideraci\u00f3n ante Sala Civil de la Corte Suprema de Justicia \u00a0 para que se cambiara el nombramiento en propiedad. Dicha solicitud fue negada \u00a0 por la Sala Plena de dicho tribunal, primero, mediante los oficios PCJ No.1382, \u00a0 1384 y 1385 del 12 de agosto de 2013, por las mismas razones que motivaron el \u00a0 acto inicial de nombramiento y, segundo, el 5 de septiembre de 2013, al rechazar \u00a0 por improcedente el recurso de reposici\u00f3n que se interpuso contra la precitada \u00a0 decisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>2.4.3.3. Como se expuso,\u00a0la acci\u00f3n de tutela es improcedente en los casos en que \u00e9sta no se \u00a0 presenta dentro de un t\u00e9rmino prudencial y razonable, en relaci\u00f3n con el momento \u00a0 en que se presenta la afectaci\u00f3n o amenaza de los derechos fundamentales \u00a0 invocados.\u00a0En todo caso, la razonabilidad del \u00a0 lapso debe ser analizada por el juez de tutela a la luz de los criterios que \u00a0 sobre la materia ha establecido la jurisprudencia constitucional. As\u00ed, para \u00a0 hacer el an\u00e1lisis del requisito de inmediatez, en primer lugar, es \u00a0 necesario identificar el momento en que se present\u00f3 la presunta vulneraci\u00f3n o la \u00a0 amenaza de los derechos fundamentales invocados por los accionantes y, en \u00a0 segundo lugar, verificar si el t\u00e9rmino transcurrido entre dicho suceso y la \u00a0 presentaci\u00f3n de la acci\u00f3n de tutela no es un tiempo prolongado e irrazonable \u00a0 para reclamar la protecci\u00f3n constitucional. \u00a0 \u00a0<\/p>\n<p>2.4.3.4. Respecto del primer punto, la Corte considera que, contrario a \u00a0 lo sostenido por los jueces de tutela de ambas instancias, la conducta que causa \u00a0 la vulneraci\u00f3n no es el acto inicial de nombramiento en provisionalidad de los \u00a0 accionantes -10 de mayo de 2012-, sino los actos posteriores que denegaron los \u00a0 nombramientos en propiedad -de 12 de agosto y 5 de septiembre de 2013-: (i) las \u00a0 decisiones contenidas en los oficios PCJ No.1382, 1384 y 1385 del 12 de agosto \u00a0 de 2013; y (ii) la declaraci\u00f3n de improcedencia del recurso de reposici\u00f3n contra \u00a0 los actos anteriores, del 5 de septiembre de 2013. \u00a0 \u00a0<\/p>\n<p>2.4.3.5. La Corte arriba a esta conclusi\u00f3n, por las siguientes razones: \u00a0 (i) a la fecha de expedici\u00f3n del acto de nombramiento no hab\u00eda certeza respecto \u00a0 de la naturaleza de dichos cargos, pues tan solo hab\u00eda un concepto de la Unidad \u00a0 de Administraci\u00f3n de Carrera Judicial, que no ten\u00eda car\u00e1cter vinculante; (ii) \u00a0 los actos administrativos -Acuerdo y Circular- que modificaron la situaci\u00f3n \u00a0 inicial de incertidumbre, por cuanto definieron la naturaleza y la forma en que \u00a0 se deb\u00edan proveer los cargos de los funcionarios de restituci\u00f3n de tierras, \u00a0 fueron dictados en mayo de 2013, por la Sala Administrativa del Consejo Superior \u00a0 de la Judicatura, los cuales gozan de presunci\u00f3n de legalidad y tienen car\u00e1cter \u00a0 vinculante; (iii) de este modo, la presunta violaci\u00f3n de los derechos \u00a0 fundamentales no se caus\u00f3 con los primeros actos de nombramiento en \u00a0 provisionalidad, dada la justificaci\u00f3n de la conducta del nominador ante la \u00a0 ausencia de definici\u00f3n de la naturaleza de los cargos; (iv) en cambio, la \u00a0 vulneraci\u00f3n pudo haberse causado cuando la entidad accionada neg\u00f3 la solicitud \u00a0 de reconsideraci\u00f3n y el subsiguiente recurso de reposici\u00f3n -agosto y septiembre \u00a0 de 2013-, con desconocimiento de los actos administrativos vinculantes que \u00a0 entraron a regular el tema y de la competencia que le confiere la Constituci\u00f3n a \u00a0 la Sala Administrativa del Consejo Superior de la Judicatura para definir la \u00a0 naturaleza de dichos cargos. \u00a0 \u00a0<\/p>\n<p>2.4.3.6. Sobre la base de lo anterior, la Corte estima que el tiempo que \u00a0 transcurri\u00f3 entre el \u00faltimo acto que presuntamente caus\u00f3 la vulneraci\u00f3n -5 de \u00a0 septiembre de 2013- y la interposici\u00f3n de la acci\u00f3n de tutela -24 de octubre de \u00a0 2013-, aproximadamente dos meses, es un t\u00e9rmino prudente y razonable para \u00a0 solicitar la protecci\u00f3n de los derechos fundamentales. \u00a0 \u00a0<\/p>\n<p>2.4.4. Conclusi\u00f3n parcial. \u00a0 \u00a0<\/p>\n<p>En consecuencia, la Corte concluye que, en el presente caso, se satisface \u00a0 el requisito de inmediatez, porque los accionantes interpusieron de manera \u00a0 oportuna la acci\u00f3n de tutela contra los actos administrativos expedidos por el \u00a0 nominador -Sala Plena de la Corte Suprema de Justicia- por medio de los cuales \u00a0 neg\u00f3 el cambio de sus nombramientos en provisionalidad, tras haber sido definido \u00a0 que se trataba de cargos permanentes y nombramientos en propiedad. \u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>2.5. Subsidiariedad. \u00a0 \u00a0<\/p>\n<p>2.5.1. Jurisprudencia constitucional. \u00a0 Reiteraci\u00f3n. \u00a0 \u00a0<\/p>\n<p>2.5.1.1. El articulo 86 Superior establece la \u00a0 acci\u00f3n de tutela como un procedimiento constitucional, destinado a la protecci\u00f3n \u00a0 de los derechos fundamentales, caracterizada por su car\u00e1cter residual y \u00a0 subsidiario, esto significa que, s\u00f3lo proceder\u00e1 cuando el afectado no disponga \u00a0 de otro medio de defensa judicial, salvo que aquella se utilice como mecanismo \u00a0 transitorio para evitar un perjuicio irremediable.[33] \u00a0 \u00a0<\/p>\n<p>2.5.1.2. La jurisprudencia de esta Corporaci\u00f3n ha reiterado \u00a0 que en el \u00e1mbito del derecho administrativo, la acci\u00f3n de tutela es improcedente \u00a0 como mecanismo principal para proteger derechos fundamentales que resulten \u00a0 amenazados o vulnerados con ocasi\u00f3n de la expedici\u00f3n de actos administrativos[34], \u00a0 por cuanto para controvertir la legalidad de estos est\u00e1n previstas acciones \u00a0 id\u00f3neas en la jurisdicci\u00f3n de lo contencioso administrativo[35], en la cual se puede \u00a0 solicitar desde la demanda como medida cautelar la suspensi\u00f3n del acto[36]. \u00a0 \u00a0<\/p>\n<p>2.5.1.3. Espec\u00edficamente, respecto de la \u00a0 procedencia excepcional de la acci\u00f3n de tutela contra actos administrativos \u00a0 expedidos en el marco de un concurso de m\u00e9ritos, la Sala Plena de este Tribunal \u00a0 Constitucional, en Sentencia SU-133 de 1998[37], \u00a0 precis\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201c (\u2026) esta \u00a0 Corporaci\u00f3n ha considerado que la vulneraci\u00f3n de los derechos a la igualdad, al \u00a0 trabajo y debido proceso, de la cual son v\u00edctimas las personas acreedoras a un \u00a0 nombramiento en un cargo de carrera cuando no son designadas pese al hecho de \u00a0 haber obtenido el primer lugar en el correspondiente concurso, no encuentran \u00a0 soluci\u00f3n efectiva ni oportuna en un proceso ordinario que supone unos tr\u00e1mites \u00a0 m\u00e1s dispendiosos y demorados que los de la acci\u00f3n de tutela y por lo mismo \u00a0 dilatan y mantienen en el tiempo la violaci\u00f3n de un derecho fundamental que \u00a0 requiere protecci\u00f3n inmediata.\u201d \u00a0 \u00a0<\/p>\n<p>2.5.1.4. En esa l\u00ednea, en la Sentencia SU-613 de 2002, la Corte determin\u00f3 que: \u00a0 \u00a0<\/p>\n<p>\u201c\u2026 existe una \u00a0 clara l\u00ednea jurisprudencial seg\u00fan la cual la acci\u00f3n de tutela es el mecanismo \u00a0 id\u00f3neo para controvertir la negativa a proveer cargos de carrera en la \u00a0 administraci\u00f3n judicial de conformidad con los resultados de los concursos de \u00a0 m\u00e9ritos, pues con ello se garantizan no s\u00f3lo los derechos a la igualdad, al \u00a0 debido proceso y al trabajo, sino tambi\u00e9n el acceso a los cargos p\u00fablicos, y se \u00a0 asegura la correcta aplicaci\u00f3n del art\u00edculo 125 de la Constituci\u00f3n. Por lo \u00a0 mismo, al no existir motivos fundados para variar esa l\u00ednea, la Sala considera \u00a0 que debe mantener su posici\u00f3n y proceder al an\u00e1lisis material del caso. Obrar en \u00a0 sentido contrario podr\u00eda significar la violaci\u00f3n a la igualdad del actor, quien \u00a0 a pesar de haber actuado de buena fe y seg\u00fan la jurisprudencia constitucional, \u00a0 ante un cambio repentino de ella se ver\u00eda incluso imposibilitado para acudir a \u00a0 los mecanismos ordinarios en defensa de sus derechos.\u201d \u00a0 \u00a0<\/p>\n<p>2.5.1.5. Adem\u00e1s de lo anterior, la Corte se\u00f1al\u00f3 que la acci\u00f3n de tutela era \u00a0 procedente, cuando la persona que pretende acceder al cargo para el cual \u00a0 particip\u00f3 en un curso de m\u00e9ritos, se ve expuesta al riesgo de que el registro o \u00a0 la lista de elegibles pierda vigencia y, como consecuencia de ello, no pueda \u00a0 garantizarse la protecci\u00f3n de su derecho por las v\u00edas judiciales existentes, lo \u00a0 que generar\u00eda un perjuicio irremediable. \u00a0 \u00a0<\/p>\n<p>2.5.1.6. De acuerdo con los precedentes precitados, en la Sentencia T-090 \u00a0 de 2013, la Corte precis\u00f3 que existen dos subreglas en que procede \u00a0 excepcionalmente la tutela contra actos administrativos que regulan o ejecutan \u00a0 un proceso de concurso de m\u00e9ritos:\u00a0\u201c(i)\u00a0cuando el accionante la ejerce \u00a0 como mecanismo transitorio para evitar un perjuicio irremediable[38], \u00a0 el cual debe cumplir con los requisitos de ser inminente, de requerir medidas \u00a0 urgentes, de ser grave y de ser impostergable[39]; y,\u00a0(ii)\u00a0cuando el \u00a0 medio de defensa existe, pero en la pr\u00e1ctica es ineficaz para amparar el derecho \u00a0 fundamental cuya protecci\u00f3n se invoca y que en caso de no ser garantizado, se \u00a0 traduce en un claro perjuicio para el actor.\u201d \u00a0 \u00a0<\/p>\n<p>2.5.1.7. En conclusi\u00f3n, por regla general, la acci\u00f3n de tutela es improcedente \u00a0 contra actos administrativos que se profieran en marco de un concurso de \u00a0 m\u00e9ritos. No obstante, excepcionalmente, proceder\u00e1 el mecanismo de amparo, por un \u00a0 lado, cuando se demuestre la existencia de un perjuicio irremediable, caso en el \u00a0 cual el juez conceder\u00e1 la protecci\u00f3n transitoria mientras la jurisdicci\u00f3n \u00a0 competente decide de manera definitiva sobre la legalidad del acto, y por el \u00a0 otro, cuando a pesar de que existe un medio defensa judicial, este resulta \u00a0 ineficaz para conjurar la violaci\u00f3n del derecho fundamental invocado. \u00a0 \u00a0<\/p>\n<p>2.5.2. Subsidiaridad, \u00a0 en criterio de la accionada. \u00a0 \u00a0<\/p>\n<p>2.5.2.1. Por su \u00a0 parte, la Sala Civil y Laboral de la Corte Suprema de Justicia, fungiendo como \u00a0 jueces de tutela, denegaron la protecci\u00f3n solicitada por los actores, \u00a0 argumentando, en s\u00edntesis, la ausencia injustificada de activaci\u00f3n del mecanismo \u00a0 judicial respectivo. Adem\u00e1s que, el amparo no estaba llamado a prosperar ni \u00a0 siquiera de manera transitoria, porque no se demostr\u00f3 la existencia de un \u00a0 perjuicio irremediable. \u00a0 \u00a0<\/p>\n<p>2.5.2.2. En las circunstancias planteadas, la Sala \u00a0 estima necesario determinar si en este caso se cumple con el requisito de \u00a0 subsidiariedad, o si por el contrario existe un mecanismo de defensa judicial \u00a0 eficaz diferente a la acci\u00f3n de tutela para dirimir la controversia planteada \u00a0 por los accionantes. \u00a0 \u00a0<\/p>\n<p>2.5.3. Examen de subsidiaridad. \u00a0 \u00a0<\/p>\n<p>2.5.3.1. En cuanto al requisito de subsidiariedad, los accionantes \u00a0 manifestaron que la jurisprudencia constitucional[40], \u00a0 ha establecido que la acci\u00f3n de tutela es el mecanismo id\u00f3neo y eficaz con el \u00a0 que cuenta una persona para controvertir la negativa a proveer cargos de \u00a0 carrera, de conformidad con los resultados publicados en la listas de elegibles \u00a0 por los concursos de m\u00e9rito. En ese sentido, afirmaron que dicha acci\u00f3n \u00a0 constitucional era el \u00fanico mecanismo eficaz con el que contaban, para que los \u00a0 jueces estudiaran los fundamentos de los actos de nombramiento, los cuales \u00a0 consideran han deca\u00eddo por causa de un hecho nuevo, que consiste en el \u00a0 Acuerdo y la Circular expedida por la Sala Administrativa del Consejo Superior \u00a0 de la Judicatura. \u00a0 \u00a0<\/p>\n<p>2.5.3.2. En el caso sub examine, se tiene que lo \u00a0 pretendido por los accionantes es que se ordene a la Sala Plena de la Corte \u00a0 Suprema de Justicia que los nombre, en propiedad, en los cargos de Magistrado de \u00a0 Tribunal Superior, Sala Civil, especializada en restituci\u00f3n de tierras. En otros \u00a0 t\u00e9rminos, pretenden mediante la acci\u00f3n de tutela desvirtuar la presunci\u00f3n de \u00a0 legalidad que recae sobre los actos administrativos, que resolvieron mantener el \u00a0 nombramiento en provisionalidad, para en su lugar, se profieran los actos que \u00a0 provean los cargos en propiedad.\u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>2.5.3.3. Los actos administrativos que expide la Sala \u00a0 Plena de la Corte Suprema de Justicia, en cumplimiento de la funci\u00f3n \u00a0 administrativa que desempe\u00f1a como nominador, son susceptibles de ser demandados \u00a0 ante la jurisdicci\u00f3n de lo contencioso administrativo, a trav\u00e9s del medio de \u00a0 control de nulidad y restablecimiento del derecho (Ley 1437 de 2011, art\u00edculo \u00a0 138). \u00a0 \u00a0<\/p>\n<p>2.5.3.4. De este \u00a0 modo, por regla general, la acci\u00f3n de nulidad y restablecimiento del derecho es \u00a0 el mecanismo id\u00f3neo y eficaz para demandar la legalidad del acto administrativo \u00a0 de nombramiento de un funcionario judicial, que por ejemplo, pretende acceder al \u00a0 cargo por hacer parte de una lista de elegibles conformada por el \u00f3rgano \u00a0 competente en virtud de un concurso de m\u00e9ritos. Por esta raz\u00f3n, en principio, se \u00a0 aparta o excluye al juez de tutela del conocimiento de dichas controversias. \u00a0 \u00a0<\/p>\n<p>2.5.3.5. No obstante, \u00a0 la jurisprudencia constitucional ha determinado que existen casos excepcionales \u00a0 en los que no opera la regla general de improcedencia de la acci\u00f3n de tutela \u00a0 contra este tipo de actos administrativos. El primer supuesto, es cuando el medio de defensa existe, pero en la pr\u00e1ctica \u00a0 es ineficaz para amparar el derecho fundamental cuya protecci\u00f3n se invoca y que \u00a0 en caso de no ser garantizado, se traduce en un claro perjuicio para el actor; y \u00a0 el segundo, cuando el accionante ejerce la acci\u00f3n de tutela como mecanismo \u00a0 transitorio para evitar un perjuicio irremediable, el cual debe cumplir con los \u00a0 requisitos de ser inminente, de requerir medidas urgentes, de ser grave y de ser \u00a0 impostergable. De ah\u00ed que, en ciertos casos, cuando la \u00a0 acci\u00f3n de tutela se interpone contra actos administrativos relacionados con \u00a0 concursos de m\u00e9ritos, el perjuicio irremediable que se pretender\u00eda evitar son \u00a0 las consecuencias negativas que se derivan de la p\u00e9rdida de vigencia de la lista \u00a0 de elegibles, las cuales no se podr\u00edan impedir si exige al tutelante el previo \u00a0 agotamiento de los medios de control dispuestos en la jurisdicci\u00f3n de lo \u00a0 contencioso administrativo para reclamar la protecci\u00f3n de su derecho, por la \u00a0 extensa duraci\u00f3n de su tr\u00e1mite. En esa l\u00ednea de argumentaci\u00f3n, la jurisprudencia \u00a0 constitucional ha se\u00f1alado que \u201clos registros de elegibles tienen vocaci\u00f3n temporal y \u00a0 exigir en todo caso la actuaci\u00f3n ante la v\u00eda judicial contenciosa puede acarrear \u00a0 demoras que har\u00edan nugatorio el derecho afectado ante la inminente p\u00e9rdida de \u00a0 vigencia del registro de elegibles antes de que se pudiera adoptar una decisi\u00f3n \u00a0 en tal jurisdicci\u00f3n.\u201d[41] \u00a0 \u00a0<\/p>\n<p>2.5.3.6. En apoyo a \u00a0 lo anterior, esta Corporaci\u00f3n, en la Sentencia SU-913 de 2009[42], \u00a0 estableci\u00f3: \u00a0 \u00a0<\/p>\n<p>\u00a0\u201c5.2. Considera \u00a0 la Corte que en materia de concursos de m\u00e9ritos para la provisi\u00f3n de cargos \u00a0 de carrera se ha comprobado que no se encuentra soluci\u00f3n efectiva ni oportuna \u00a0 acudiendo a un proceso ordinario o contencioso, en la medida que su tr\u00e1mite \u00a0 llevar\u00eda a extender en el tiempo de manera injustificada la vulneraci\u00f3n de \u00a0 derechos fundamentales que requieren de protecci\u00f3n inmediata. Esta Corte ha \u00a0 expresado, que para excluir a la tutela en estos casos, el medio judicial debe \u00a0 ser eficaz y conducente, pues se trata nada menos que de la defensa y \u00a0 realizaci\u00f3n de derechos fundamentales, ya que no tendr\u00eda objeto alguno enervar \u00a0 el mecanismo de tutela para sustituirlo por un instrumento previsto en el \u00a0 ordenamiento legal que no garantice la supremac\u00eda de la Constituci\u00f3n en el caso \u00a0 particular[43].\u201d \u00a0 \u00a0<\/p>\n<p>2.5.1.6. En el presente caso, \u00a0 los accionantes aprobaron el concurso de m\u00e9ritos convocado mediante Acuerdo \u00a0 No.4528 de 2008, por lo cual fueron inscritos en un Registro de elegibles de los \u00a0 Magistrados de Tribunal Superior -Sala Civil-. Dicho registro data del 17 de \u00a0 julio de 2011[44] \u00a0y, de acuerdo con lo establecido en el art\u00edculo 165 de la Ley 270 de 1996, \u00a0 cuenta con un periodo de vigencia de cuatro a\u00f1os, lo que significa que su \u00a0 vigencia se extender\u00eda hasta mediados del a\u00f1o 2015. A pesar de lo anterior, la \u00a0 Sala Plena de la Corte Suprema de Justicia, el 10 de mayo de 2012, nombr\u00f3 en \u00a0 provisionalidad a los accionantes en el cargo de Magistrado de Tribunal Superior \u00a0 -Sala Civil-, en la especialidad en restituci\u00f3n de tierras, solicitando a la \u00a0 Sala Administrativa del Consejo Superior de la Judicatura convocar a un concurso \u00a0 espec\u00edfico para la provisi\u00f3n de los cargos mencionados. \u00a0 \u00a0<\/p>\n<p>En cuanto a la solicitud de la \u00a0 autoridad nominadora, indicaron los accionantes que: \u201ctan claro es para la \u00a0 Sala Administrativa que nuestros nombramientos son en propiedad, y no se \u00a0 requiere un nuevo concurso, que en el Acuerdo No.PSAA13-9939 de junio de 2013, \u00a0 para la provisi\u00f3n de los cargos de Funcionarios de la Rama Judicial, no fueron \u00a0 incluidos los cargos de Magistrados especializados en restituci\u00f3n de tierras \u00a0 (\u2026). De all\u00ed que la actual convocatoria este dirigida a la selecci\u00f3n, en entre \u00a0 otros, de los cargos de Magistrado de Tribunal Superior Sala Civil, de cuyo \u00a0 registro de elegibles deber\u00e1n ser nombrados los Magistrados de los Tribunales \u00a0 superiores Sala Civil, especializados en restituci\u00f3n de tierras\u201d[45]. En \u00a0 efecto, la Corte advierte que la Sala Administrativa convoc\u00f3 en el a\u00f1o 2013, \u00a0 mediante el acuerdo precitado, a un concurso para proveer cargos de funcionarios \u00a0 de la Rama Judicial, en los cuales aunque no incluy\u00f3 espec\u00edficamente el \u00a0 cargo de Magistrado especializado en restituci\u00f3n de tierras, s\u00ed incorpor\u00f3 el de \u00a0 \u201cMagistrado de Tribunal Superior \u2013Sala Civil\u201d[46]. \u00a0 En consecuencia, es posible inferir que, en el caso concreto, el derecho que \u00a0 invocan los accionantes a \u00a0permanecer en los cargos de carrera, que ocupan \u00a0 actualmente, en provisionalidad, se encuentra amenazado por la realizaci\u00f3n de \u00a0 este nuevo concurso, en tanto, tiene por objeto proveer, entre otros cargos, los \u00a0 de Magistrado de Tribunal Superior &#8211; Sala Civil, de los que hace parte la \u00a0 especialidad en restituci\u00f3n de tierras. \u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>Unido a lo anterior, la Corte \u00a0 considera que la demanda de tutela satisface el requisito de subsidiariedad, en \u00a0 raz\u00f3n a que, el medio de control judicial ordinario (acci\u00f3n de nulidad y \u00a0 restablecimiento del derecho) resulta ineficaz para la protecci\u00f3n de los \u00a0 derechos reclamados, porque en el tiempo prolongado que implica su tr\u00e1mite, \u00a0 vencer\u00eda el Registro de elegibles y, por consiguiente, no se podr\u00eda a t\u00edtulo de \u00a0 restablecimiento del derecho nombrar a los accionantes en propiedad, debido a \u00a0 que, simplemente ya estar\u00edan excluidos de ese listado. Dicha circunstancia \u00a0 constituye un perjuicio irremediable que, en atenci\u00f3n de las consideraciones \u00a0 expuestas, se encuadra en una de las hip\u00f3tesis, para que, de manera excepcional, \u00a0 se declare procedente la acci\u00f3n de tutela contra actos administrativos. \u00a0 \u00a0<\/p>\n<p>3. Problema jur\u00eddico constitucional. \u00a0 \u00a0<\/p>\n<p>3.1. La Sala Plena de la Corte \u00a0 Constitucional resolver\u00e1 si la Sala Plena de la Corte Suprema de Justicia \u00a0 vulner\u00f3 el derecho fundamental al debido proceso administrativo, de los \u00a0 accionantes al no aplicar, sin motivaci\u00f3n alguna, los actos administrativos \u00a0 (Acuerdo y Circular), expedidos por la Sala Administrativa del Consejo Superior \u00a0 de la Judicatura, que definieron la naturaleza y la forma en que deb\u00eda proveerse \u00a0 el cargo de Magistrado de Tribunal Sala Civil, especialidad en restituci\u00f3n de \u00a0 tierras.\u00a0 \u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>3.2. Dado que los accionantes desempe\u00f1an \u00a0 actualmente el cargo referido en provisionalidad, no se encuentran desconocidos \u00a0 sus derechos al trabajo y de acceso al desempe\u00f1o de funciones y cargos \u00a0 p\u00fablicos. \u00a0 \u00a0<\/p>\n<p>4. Cargo: vulneraci\u00f3n del derecho al \u00a0 debido proceso administrativo (art. 29 CP). \u00a0 \u00a0<\/p>\n<p>4.1. Concepto de inconstitucionalidad en la demanda. \u00a0 \u00a0<\/p>\n<p>Como se puso de presente al exponer los \u00a0 argumentos de los accionantes[47], \u00a0 la demanda se\u00f1ala que el tribunal accionado vulner\u00f3 sus derechos fundamentales, \u00a0 por haber negado la solicitud de reconsideraci\u00f3n y, haber rechazado el recurso \u00a0 de reposici\u00f3n, que fueron presentados para efectuar su nombramiento en \u00a0 propiedad, con base en lo dispuesto en el Acuerdo y la Circular de la Sala \u00a0 Administrativa del Consejo Superior de la Judicatura. De este modo, le \u00a0 corresponder\u00e1 a la Corte verificar si la autoridad accionada, en condici\u00f3n de \u00a0 nominador, vulner\u00f3 el derecho al debido proceso administrativo, por incurrir en \u00a0 un defecto material al dejar de aplicar las normas (actos administrativos \u00a0 vinculantes), que definieron la naturaleza y la forma en que se deb\u00edan proveer \u00a0 las plazas para Magistrados especializados en restituci\u00f3n de tierras. \u00a0 \u00a0<\/p>\n<p>4.2. Par\u00e1metros normativos. \u00a0 \u00a0<\/p>\n<p>Para juzgar este caso, se emplear\u00e1n las \u00a0 categor\u00edas establecidas para el estudio de la acci\u00f3n de tutela contra \u00a0 providencias judiciales. Como lo ha precisado esta Corporaci\u00f3n en otras \u00a0 oportunidades[48], \u00a0 ello facilita el an\u00e1lisis de la afectaci\u00f3n del derecho al debido proceso \u00a0 administrativo, con la consideraci\u00f3n de que aunque diferentes en su concepci\u00f3n \u00a0 inicial, se presentan como \u00fatiles para la \u00a0 identificaci\u00f3n de actuaciones de la administraci\u00f3n que involucran la afectaci\u00f3n \u00a0 de los derechos fundamentales del ciudadano[49]. Por esta raz\u00f3n, m\u00e1s adelante se har\u00e1 \u00e9nfasis en el defecto \u00a0 material o sustantivo. \u00a0 \u00a0<\/p>\n<p>4.3. Regla constitucional de la carrera administrativa en la provisi\u00f3n \u00a0 de cargos de la Rama Judicial. \u00a0 \u00a0<\/p>\n<p>4.3.2. \u00a0 Para los cargos de carrera administrativa, el ingreso como el ascenso se \u00a0 realizan previo el cumplimiento de los requisitos y condiciones fijadas por la \u00a0 ley, con el objeto de\u00a0\u201cdeterminar los m\u00e9ritos y \u00a0 calidades de los aspirantes\u201d.\u00a0A su vez, que\u00a0el retiro de dichos cargos se har\u00e1 por \u201ccalificaci\u00f3n no \u00a0 satisfactoria en el desempe\u00f1o del empleo; por violaci\u00f3n del r\u00e9gimen \u00a0 disciplinario y por las dem\u00e1s causales previstas en la Constituci\u00f3n o la ley.\u201d (C.P. art. 125) \u00a0 \u00a0<\/p>\n<p>4.3.3. La Corte\u00a0ha reiterado en \u00a0 su jurisprudencia que la carrera administrativa es el mecanismo por excelencia \u00a0 para el ingreso, permanencia, promoci\u00f3n y retiro a los empleos del Estado[51], lo que significa su aplicaci\u00f3n general \u00a0 y, por ende, la interpretaci\u00f3n restrictiva de las excepciones consagradas en la \u00a0 Constituci\u00f3n[52]. As\u00ed mismo, este Tribunal ha \u00a0 determinado que la carrera administrativa, tiene \u00a0 por objeto\u00a0la garant\u00eda del derecho a la igualdad de \u00a0 oportunidades para el acceso a cargos y funciones p\u00fablicas (CP, 40.7),\u00a0la \u00a0 b\u00fasqueda de la eficiencia y la eficacia en el servicio p\u00fablico para el \u00a0 cumplimiento de los fines del Estado (CP,\u00a01, 2, 122 a \u00a0 131 y 209), y la protecci\u00f3n de los derechos subjetivos a los que tienen derecho \u00a0 las personas vinculadas a la carrera (CP, 53 y 125) y se funda en\u00a0el m\u00e9rito de \u00a0 los aspirantes, para lo cual la Carta Pol\u00edtica prescribi\u00f3 el concurso p\u00fablico \u00a0 como el mecanismo id\u00f3neo para establecer el m\u00e9rito y las calidades de los mismos[53].[54] \u00a0 \u00a0<\/p>\n<p>4.3.4. Ahora bien, la Corte ha \u00a0 indicado que de conformidad con el art\u00edculo 256-1 de la Constituci\u00f3n, la carrera \u00a0 judicial constituye un sistema especial de carrera administrativa, por lo cual \u00a0 se encuentra sujeta a los criterios impuestos por el art\u00edculo 125 superior[55]. \u00a0 Esto implica que, por regla general, el concurso p\u00fablico de m\u00e9ritos debe ser \u00a0 utilizado para proveer cargos en la Rama Judicial, en tanto, constituye el \u00a0 procedimiento preferente para garantizar que los ciudadanos m\u00e1s calificados para \u00a0 el efecto, desempe\u00f1en las funciones que demanda la trascendental actividad de \u00a0 administrar justicia. Vale la pena precisar que las reglas del concurso p\u00fablico \u00a0 de m\u00e9ritos para proveer cargos en la rama judicial se encuentran se\u00f1aladas en \u00a0 los art\u00edculos 156[56], \u00a0 164 y siguientes de la Ley 270 de 1996, conocida como Ley Estatutaria de la \u00a0 Administraci\u00f3n de Justicia, modificada por Ley 1285 de 2009. \u00a0 \u00a0<\/p>\n<p>4.3.5. En armon\u00eda con lo anterior, en cuanto a la selecci\u00f3n de \u00a0 personas para cargos de la rama judicial, la Corte en la Sentencia C-713 de 2008 fij\u00f3 la regla conforme a la \u00a0 cual los funcionarios judiciales deben ser elegidos de una lista o registro \u00a0 conformado mediante concurso p\u00fablico de m\u00e9ritos, sin importar que su cargo fuese \u00a0 tan s\u00f3lo temporal[57]. \u00a0 \u00a0<\/p>\n<p>4.3.6. Luego, en la Sentencia \u00a0 C-333 de 2012, la Corte tuvo la oportunidad de realizar un estudio de \u00a0 constitucionalidad sobre la carrera judicial y la provisi\u00f3n de cargos mediante \u00a0 concurso p\u00fablico de m\u00e9ritos, con ocasi\u00f3n de una demanda promovida contra el \u00a0 art\u00edculo 67 de la Ley 975 de 2005[58], \u00a0 referente al sistema de elecci\u00f3n de los magistrados de justicia y paz de los \u00a0 Tribunales Superiores de Distrito Judicial. A partir de la regla fijada en la \u00a0 sentencia C-713 de 2008, la Corte concluy\u00f3 que, en este caso, la norma legal \u00a0 acusada violaba el art\u00edculo 125 de la Constituci\u00f3n que impone como regla la \u00a0 carrera administrativa fundada en el m\u00e9rito, como criterio principal y \u00a0 primordial de selecci\u00f3n de las personas dedicadas a la funci\u00f3n p\u00fablica. Arrib\u00f3 a \u00a0 dicha conclusi\u00f3n, por cuanto, el art\u00edculo 67 de la ley de justicia y paz, no \u00a0 contempl\u00f3 un sistema de elecci\u00f3n que, si bien pod\u00eda ser sensible a las \u00a0 especiales condiciones de las funciones a realizar, se fundara en una elecci\u00f3n \u00a0 p\u00fablica basada en el m\u00e9rito. En consecuencia, declar\u00f3 la exequibilidad de la \u00a0 norma acusada, en el entendido de que tales cargos se deben proveer seg\u00fan el \u00a0 concurso p\u00fablico (Registro de elegibles) vigente para cargos en la rama \u00a0 judicial. \u00a0 \u00a0<\/p>\n<p>4.3.7. \u00a0 Posteriormente, dicha regla de decisi\u00f3n fue reiterada en la sentencia C-532 de \u00a0 2013, en la que, en desarrollo del estudio de la constitucionalidad del art\u00edculo \u00a0 28 de la Ley 1592 de 2012, se parti\u00f3 del mismo supuesto resuelto en la anterior \u00a0 oportunidad. En ambos an\u00e1lisis se planteaba el desconocimiento del concurso \u00a0 p\u00fablico de m\u00e9ritos como requisito constitucional para acceder a la carrera \u00a0 judicial, incluso en cargos con vocaci\u00f3n de transitoriedad, como lo ser\u00edan los \u00a0 de la jurisdicci\u00f3n de justicia y paz. La Corte\u00a0decidi\u00f3 \u00a0 que la norma demandada era exequible entendiendo que\u00a0los empleos a los que se \u00a0 refiere dicho precepto legal, es decir los cargos de magistrados de Tribunal \u00a0 Superior de Distrito Judicial, deber\u00e1n ser provistos de las listas de elegibles \u00a0 vigentes enviadas por la Sala Administrativa del Consejo Superior de la \u00a0 Judicatura en materia penal por ser esta especialidad en la que se enmarca la \u00a0 actuaci\u00f3n de los Jueces de Justicia y paz. \u00a0 \u00a0<\/p>\n<p>4.3.8. A la luz de los precedentes decantados, es claro que la provisi\u00f3n \u00a0 de los cargos de la Rama Judicial se debe hacer a trav\u00e9s de las reglas del \u00a0 concurso p\u00fablico y abierto contenido en la Ley 270 de 1996 y, teniendo en cuenta \u00a0 la lista de elegibles vigente. En todo caso, la vocaci\u00f3n transitoria del cargo \u00a0 no podr\u00e1 entenderse como impedimento, para que, en la selecci\u00f3n del funcionario \u00a0 que lo vaya ocupar, se aplique el r\u00e9gimen de carrera judicial. Dicho r\u00e9gimen \u00a0 protege los derechos y garant\u00edas constitucionales de aspirantes y servidores \u00a0 p\u00fablicos, al mismo tiempo que, cumple los fines estatales de transparencia y \u00a0 eficacia, comprometidos en los mecanismos de ingreso al servicio p\u00fablico. \u00a0 \u00a0<\/p>\n<p>4.4. Competencia constitucional de la Sala Administrativa del \u00a0 Consejo Superior de la Judicatura para reglamentar y administrar la carrera \u00a0 judicial. Reiteraci\u00f3n de jurisprudencia. \u00a0 \u00a0<\/p>\n<p>4.4.1. La Constituci\u00f3n de 1991, en el art\u00edculo 254, dispone \u00a0 que el Consejo Superior de la Judicatura est\u00e1 compuesto por las salas \u00a0 Administrativa y Jurisdiccional Disciplinaria; en el numeral 1\u00b0 del art\u00edculo \u00a0 256, establece que dicho \u00f3rgano tiene la atribuci\u00f3n de administrar la carrera \u00a0 judicial; y en el numeral 2\u00b0 del art\u00edculo 257 le asigna la funci\u00f3n de crear, \u00a0 suprimir, fusionar y trasladar cargos en la administraci\u00f3n de justicia. \u00a0 \u00a0<\/p>\n<p>4.4.2. En consideraci\u00f3n de las anteriores funciones \u00a0 constitucionales, el art\u00edculo 75 de la Ley 270 de 1996, Estatutaria de la \u00a0 Administraci\u00f3n de Justicia, modificada por Ley 1285 de 2009, otorga a la Sala \u00a0 Administrativa la funci\u00f3n general de administrar la rama judicial, mientras que, \u00a0 el art\u00edculo 85, le concede la labor de administrar y reglamentar la carrera \u00a0 judicial de acuerdo con las normas constitucionales y con sujeci\u00f3n a lo previsto \u00a0 por el legislador. Al respecto, la Corte Constitucional, en la Sentencia C-265 \u00a0 de 1993, sostuvo: \u00a0 \u00a0<\/p>\n<p>\u201cLa Sala administrativa por su \u00a0 parte, tambi\u00e9n fue creada org\u00e1nicamente con funciones propias, para cumplir \u00a0 funciones administrativas, con representaci\u00f3n de las corporaciones nominadoras y \u00a0 como garant\u00eda de la autonom\u00eda administrativa de la Rama Judicial perseguida por \u00a0 el Constituyente.\u00a0 Esta Sala Administrativa ejerce funciones que tienen su \u00a0 fuente en la Constituci\u00f3n y la ley (posteriormente en la ley estatutaria de la \u00a0 administraci\u00f3n de justicia y en otras leyes especiales), tales funciones son \u00a0 administrativas por su propia naturaleza y traducen la representaci\u00f3n unificada \u00a0 de la Rama Judicial que expresan las Corporaciones nominadoras (Corte \u00a0 Constitucional, Corte Suprema de Justicia y Consejo de Estado).\u201d \u00a0 \u00a0<\/p>\n<p>4.4.3. Posteriormente, en la sentencia C-037 de 1996, la \u00a0 Corte analiz\u00f3 entre otras disposiciones contenidas en la Ley 270 de 1996, \u00a0 aquellas relacionadas con las funciones otorgadas a la Sala Administrativa del \u00a0 Consejo Superior de la Judicatura. De manera general, la Sala Plena verific\u00f3 que \u00a0 en desarrollo de los art\u00edculos 254, 256 y 257 de la Constituci\u00f3n, el art\u00edculo 85 \u00a0 de esa Ley prev\u00e9 que corresponde a la Sala Administrativa de esa Corporaci\u00f3n \u00a0 administrar la Rama Judicial y reglamentar la carrera administrativa en ese \u00a0 sector[59], \u00a0 siempre y cuando no se trate de materias de competencia exclusiva del \u00a0 legislador, en los t\u00e9rminos previstos en los \u00a0 art\u00edculos 125 y 150-23[60] \u00a0de la Carta Pol\u00edtica. \u00a0 \u00a0<\/p>\n<p>4.4.4. En concordancia con lo anterior, en la Sentencia \u00a0 SU-539 de 2012, la Corte determin\u00f3 que las \u00a0 funciones del Consejo Superior de la Judicatura, particularmente aquella \u00a0 relativa a su facultad de reglamentar la carrera judicial, se inscribe en lo que \u00a0 la jurisprudencia constitucional ha denominado \u201cpotestad reglamentaria de los \u00a0 \u00f3rganos constitucionales\u201d[61], la cual se concreta en la expedici\u00f3n \u00a0 de las normas de car\u00e1cter general que sean necesarias para la cumplida ejecuci\u00f3n \u00a0 de la ley, en este caso, la Ley 270 de 1996. \u00a0 \u00a0<\/p>\n<p>4.4.5. A partir de lo \u00a0 expuesto, la Corte concluye que el Consejo Superior de la Judicatura tiene una \u00a0 competencia normativa o potestad reglamentaria en el \u00e1mbito de la carrera \u00a0 judicial y, por ende, la facultad de adoptar disposiciones que desarrollen el \u00a0 sentido de la ley para hacerla ejecutable. \u00a0 \u00a0<\/p>\n<p>4.5. Marco jur\u00eddico de la naturaleza de los cargos de Magistrados \u00a0 Especializados en Restituci\u00f3n de Tierras y Jueces Civiles del Circuito \u00a0 Especializados en Restituci\u00f3n de tierras y de la forma de proveerlos. \u00a0 \u00a0<\/p>\n<p>4.5.1. El \u00a0 Legislador en el art\u00edculo 119 de la Ley 1448 de 2011 (Ley de V\u00edctimas y \u00a0 Restituci\u00f3n de Tierras), \u00a0 dispuso que el Consejo Superior de la Judicatura ser\u00eda el encargado de la \u00a0 creaci\u00f3n de los cargos de Magistrados de los Tribunales Superiores y Jueces Civiles del \u00a0 Circuito, especializados en restituci\u00f3n de tierras, as\u00ed como de los cargos de \u00a0 los dem\u00e1s funcionarios que sean necesarios para el cumplimiento de la Ley, de \u00a0 conformidad con el numeral 5 del art\u00edculo 85 de la Ley 270 de 1996 y dem\u00e1s \u00a0 normas concordantes[62]. \u00a0 \u00a0<\/p>\n<p>4.5.2. La disposici\u00f3n normativa en la que la Ley 1448 de 2011 \u00a0 fundament\u00f3 la creaci\u00f3n de los cargos mencionados (numeral 5 del art\u00edculo 85 de \u00a0 la Ley 270 de 1996), establece que una de las funciones de la Sala \u00a0 Administrativa del Consejo Superior de Judicatura, consiste en: \u201cCrear, \u00a0 ubicar, redistribuir, fusionar, trasladar, transformar y suprimir Tribunales, \u00a0 las Salas de \u00e9stos y los Juzgados, cuando as\u00ed se requiera para la m\u00e1s r\u00e1pida y \u00a0 eficaz administraci\u00f3n de justicia, (\u2026)\u201d. \u00a0 \u00a0<\/p>\n<p>4.5.3. Con base en \u00a0 las facultades legales contenidas en las normas precitadas, la Sala \u00a0 Administrativa de dicho \u00f3rgano constitucional, expidi\u00f3: (i) el Acuerdo \u00a0 PSAA12-9268, del 24 de febrero de 2012, por medio del cual cre\u00f3 los cargos de \u00a0 Magistrados de las Salas Civiles Especializadas en Restituci\u00f3n de Tierras de los \u00a0 Tribunales de Distrito Judicial de Bogot\u00e1, Cali, Cartagena, C\u00facuta y Antioquia[63]; y (ii) \u00a0 los Acuerdos PSAA12-9265, PSAA12-9266, PSAA12-9575 y PSAA12-9765 del mismo a\u00f1o, \u00a0 por medio de los cuales cre\u00f3 los cargos de Jueces Civiles del Circuito \u00a0 Especializados en Restituci\u00f3n de Tierras. \u00a0 \u00a0<\/p>\n<p>4.5.4. \u00a0 Posteriormente, a trav\u00e9s del art\u00edculo 1\u00ba del Acuerdo No.PSAA13-9866, del 13 de \u00a0 marzo de 2013, la Sala Administrativa del Consejo Superior de la \u00a0 Judicatura, entre otras cosas, precis\u00f3 que los cargos de Magistrados y Jueces \u00a0 Especializados en Restituci\u00f3n de Tierras hacen parte de la jurisdicci\u00f3n \u00a0 ordinaria civil, con la anotada especialidad[64]. \u00a0 \u00a0<\/p>\n<p>4.5.5. En concordancia con lo establecido por dicho \u00a0 acto administrativo, la misma Sala Administrativa, en la Circular PSAC13-14 del \u00a0 22 de mayo de 2013, determin\u00f3 que, a pesar de que la Ley 1448 de 2011 tiene una \u00a0 vigencia de 10 a\u00f1os, todos los cargos para el ejercicio de la restituci\u00f3n de \u00a0 tierras (magistrados, jueces y empleados) son de carrera y de car\u00e1cter \u00a0 permanente, por tanto, deben ser provistos en propiedad de los registros de \u00a0 elegibles vigentes. De tal manera, que una vez finalice el t\u00e9rmino de la \u00a0 vigencia de la Ley de V\u00edctimas y Restituci\u00f3n de Tierras, estos funcionarios \u00a0 \u201cdeben integrarse y continuar en la especialidad civil\u201d[65]. \u00a0 \u00a0<\/p>\n<p>4.5.6. A partir de lo \u00a0 anterior, la Corte concluye que los funcionarios que aprobaron el \u00a0 concurso de m\u00e9ritos convocado mediante Acuerdo No.4528 de 2008, y que pasaron a \u00a0 integrar la respectiva lista de elegibles, para ocupar los cargos de Magistrados \u00a0 de Tribunal Superior de Distrito Judicial Sala Civil, quedaron habilitados para \u00a0 ser designados en los cargos de Magistrados de Tribunal Superior &#8211; Sala Civil, \u00a0 especializados en restituci\u00f3n de tierras. Esto, debido a que: (i) la Ley 1448 de \u00a0 2011, en sus art\u00edculos 79 y 119, asign\u00f3 a las Salas Civiles de los Tribunales \u00a0 Superiores de Distrito Judicial los cargos de Magistrados especializados en \u00a0 restituci\u00f3n de tierras, estableciendo en efecto que la anotada especialidad no \u00a0 hac\u00eda parte de una jurisdicci\u00f3n diferente; (ii) la lista de elegibles \u00a0 mencionada, integrada por los accionantes, fue propuesta por la Sala \u00a0 Administrativa del Consejo Superior de la Judicatura a la autoridad nominadora \u00a0 con el fin de proveer las plazas de Magistrado de Tribunal Sala Civil, de la \u00a0 pluricitada especialidad; y (iii) los actos administrativos expedidos en marzo y \u00a0 mayo de 2013, por la Sala Administrativa, dispusieron que los cargos referidos \u00a0 hac\u00edan parte de la jurisdicci\u00f3n ordinaria civil, en tanto integraban la Sala \u00a0 Civil del respectivo Tribunal, adem\u00e1s que, se trataban de cargos de carrera \u00a0 judicial de car\u00e1cter permanentes, cuya designaci\u00f3n deb\u00eda ser en propiedad de los \u00a0 Registros de Elegibles vigentes. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>4.5.7. Ahora bien, respecto \u00a0 del asunto objeto de an\u00e1lisis, la Corte Constitucional, en la Sentencia T-319 de \u00a0 2014, tuvo la oportunidad de estudiar el tema de la creaci\u00f3n de los cargos de \u00a0 Magistrados y jueces de restituci\u00f3n de tierras, al revisar dos acciones de \u00a0 tutela que fueron interpuestas por jueces civiles del circuito, de dicha \u00a0 especialidad, en el primer caso, contra la Sala Administrativa del Consejo \u00a0 Superior de la Judicatura y la Unidad de Administraci\u00f3n de la Carrera Judicial \u00a0 y, en el segundo, contra la Sala Plena del Tribunal Superior del Distrito \u00a0 Judicial de Antioquia, por haber sido nombrados en dichas plazas, en propiedad \u00a0 y, en provisionalidad, respectivamente. \u00a0 \u00a0<\/p>\n<p>4.5.8. En esa ocasi\u00f3n, a partir de la interpretaci\u00f3n de \u00a0 las normas que reglamentan la materia, y que fueron expuestas en l\u00edneas \u00a0 anteriores, la Corte determin\u00f3 que, (i) al no hacer la Ley 1448 de 2011 salvedad \u00a0 alguna en cuanto a la calidad del cargo, deb\u00eda entenderse que se debe seguir la \u00a0 regla general consagrada en el art\u00edculo 125 Superior, el cual determina que, \u00a0 salvo las excepciones consagradas en la Constituci\u00f3n y la ley, tales empleos son \u00a0 de carrera y deber\u00e1n ser nombrados por concurso p\u00fablico. Esto, si se tiene en \u00a0 cuenta que la facultad legal (numeral 5, art. 85 de la Ley 270 de 1996) que se \u00a0 deriva de la Ley de V\u00edctimas y Restituci\u00f3n de tierras alude a la creaci\u00f3n de \u00a0 cargos de carrera o permanentes en contraposici\u00f3n a aquellos que se crean en \u00a0 virtud del art\u00edculo 63 de la Ley 270 de 1996, estos s\u00ed, con motivo de \u00a0 descongesti\u00f3n, de car\u00e1cter transitorio; y (ii) la creaci\u00f3n de tales cargos no \u00a0 constituye una jurisdicci\u00f3n diferente, sino que por el contrario se encuentra \u00a0 enmarcada en la jurisdicci\u00f3n ordinaria civil conforme al art\u00edculo 11 de la Ley \u00a0 270 de 1996; y (iii) que cuando, como ocurri\u00f3 en este caso, se ha adelantado un \u00a0 concurso de m\u00e9ritos para proveer vacantes definitivas de Jueces Civiles del \u00a0 Circuito, las cuales adem\u00e1s tienen vocaci\u00f3n de permanencia, el nombramiento no \u00a0 puede hacerse en condiciones precarias como la simple provisionalidad, sino que \u00a0 es perentorio hacerlo en propiedad[66]. \u00a0 \u00a0<\/p>\n<p>4.5.10. Con todo, para la Corte es claro que los cargos \u00a0 de Magistrados y jueces,\u00a0especializados en restituci\u00f3n de tierras: (i) \u00a0 pertenecen a la jurisdicci\u00f3n ordinaria civil; (ii) tienen vocaci\u00f3n de \u00a0 permanencia; (iii) son de carrera, es decir, que deben proveerse mediante un \u00a0 concurso de m\u00e9ritos; de ah\u00ed que, (iv) su nombramiento debe hacerse en propiedad \u00a0 de la lista de elegibles vigente, tal y como, lo consider\u00f3 la Sala \u00a0 Administrativa del Consejo Superior de la Judicatura, a trav\u00e9s del acto \u00a0 administrativo -Circular- de mayo de 2013. \u00a0 \u00a0<\/p>\n<p>4.6. Caracterizaci\u00f3n del defecto material o sustantivo en \u00a0 actuaciones administrativas. Reiteraci\u00f3n de jurisprudencia. \u00a0 \u00a0<\/p>\n<p>4.6.1. Como se expuso en l\u00edneas anteriores, la Corte considera que, \u00a0 dadas las particularidades del caso concreto, resulta pertinente aplicar de \u00a0 manera anal\u00f3gica, como lo ha hecho en otras ocasiones[67], la categor\u00eda del defecto material o \u00a0 sustantivo, propia del an\u00e1lisis que se hace en los casos de tutela contra \u00a0 providencia judicial, al \u00e1mbito de las actuaciones administrativas, con el fin \u00a0 de verificar si existi\u00f3 la violaci\u00f3n del derecho al debido proceso \u00a0 administrativo de los accionantes. Para tal efecto, la Sala Plena reiterara lo \u00a0 dispuesto en la Sentencia T-076 de 2011, en lo relacionado con la \u00a0 caracterizaci\u00f3n del defecto enunciado, a saber: \u00a0 \u00a0<\/p>\n<p>\u201cDefecto material o sustantivo, el cual concurre cuando la autoridad \u00a0 administrativa profiere el acto a partir de la aplicaci\u00f3n de normas \u00a0 inexistentes, inconstitucionales, declaradas ilegales por la jurisdicci\u00f3n \u00a0 contenciosa o abiertamente inaplicables para el caso concreto. La jurisprudencia \u00a0 tambi\u00e9n ha contemplado que la interpretaci\u00f3n irrazonable de las reglas jur\u00eddicas \u00a0 es una causal de estructuraci\u00f3n de defecto sustantivo, evento en el que se exige \u00a0 una radical oposici\u00f3n entre la comprensi\u00f3n com\u00fanmente aceptada del precepto y su \u00a0 aplicaci\u00f3n por parte de la autoridad administrativa, situaci\u00f3n que encuadra en \u00a0 lo que la doctrina define como interpretaci\u00f3n\u00a0contra legem.\u201d \u00a0 \u00a0<\/p>\n<p>4.6.2. De lo anterior, se puede colegir que el defecto \u00a0 sustancial o material se presenta cuando la autoridad administrativa aplica una \u00a0 norma claramente inaplicable al caso concreto o, visto desde otra perspectiva, \u00a0 cuando deja de aplicar la que evidentemente lo es. \u00a0 \u00a0<\/p>\n<p>4.7. El caso concreto: defecto material o sustantivo.\u00a0 \u00a0 \u00a0<\/p>\n<p>4.7.1. Como se observa de las pruebas allegadas al proceso \u00a0 de tutela, la Sala Plena del tribunal accionado, mediante acto administrativo \u00a0 del 10 de mayo de 2012, nombr\u00f3, en provisionalidad, a los accionantes en el \u00a0 cargo de Magistrado de Tribunal Sala Civil, especializado en restituci\u00f3n de \u00a0 tierras, del Distrito Judicial de Antioquia, y solicit\u00f3 a la Sala Administrativa \u00a0 del C.S.J. convocar a un concurso de m\u00e9ritos espec\u00edfico para la especialidad. \u00a0 Esto, debido a: (i) la temporalidad de la ley que cre\u00f3 los cargos (Ley 1448 de \u00a0 2011), a su juicio asimilable a la Ley de Justicia y Paz; (ii) el acuerdo que los cre\u00f3 no especific\u00f3 si eran de \u00a0 carrera o si se creaban en provisionalidad; y (iii) el concepto de la Unidad de \u00a0 Carrera que indic\u00f3 la naturaleza permanente de dichas plazas era impreciso y \u00a0 equ\u00edvoco. \u00a0 \u00a0<\/p>\n<p>4.7.2. \u00a0 Posteriormente, los accionantes, coadyuvados por los Magistrados de restituci\u00f3n \u00a0 de tierras de los otros distritos judiciales, presentaron el 20 de mayo de 2013, \u00a0 petici\u00f3n ante la entidad nominadora solicitando que fueran nombrados en \u00a0 propiedad, con fundamento en lo dispuesto en el Acuerdo y la Circular proferidas \u00a0 en mayo de 2013, por la Sala Administrativa del Consejo Superior de la \u00a0 Judicatura. Sin embargo, dicha solicitud fue negada mediante oficio del 12 de \u00a0 agosto de 2013, sin exponer una raz\u00f3n diferente a la de mantener lo decidido en \u00a0 el acto inicial de nombramiento (10 de mayo de 2012). El 23 de agosto de 2013, \u00a0 esta decisi\u00f3n fue impugnada por los peticionarios mediante recurso de \u00a0 reposici\u00f3n, el cual fue rechazado por improcedente, mediante acto del 5 de \u00a0 septiembre del mismo a\u00f1o, argumentando que los recursos de ley debieron haberse \u00a0 presentado contra el acto de nombramiento y confirmaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>4.7.3. Como qued\u00f3 explicado en la parte considerativa \u00a0 de esta providencia, en virtud del art\u00edculo 125 y 256-1 \u00a0de la Constituci\u00f3n, los \u00a0 art\u00edculos 156, 164 y siguientes de la Ley 270 de 1996, la regla general para la \u00a0 provisi\u00f3n de cargos de la Rama Judicial es la carrera administrativa, lo que \u00a0 implica la participaci\u00f3n en un concurso abierto y p\u00fablico, que basado en el \u00a0 criterio del m\u00e9rito, permita seleccionar a la persona m\u00e1s id\u00f3nea y capaz para \u00a0 desempe\u00f1ar el cargo, en este evento, relacionado con la \u00a0administraci\u00f3n de \u00a0 justicia. Es tan importante la aplicaci\u00f3n de esta regla para la efectiva \u00a0 prestaci\u00f3n del servicio y la garant\u00eda de los principios del Estado Social de \u00a0 Derecho, que la propia Corte ha se\u00f1alado que ni siquiera puede exceptuarse en \u00a0 cargos de naturaleza transitoria[68]. \u00a0 \u00a0<\/p>\n<p>4.7.4. En ese sentido, conforme a la interpretaci\u00f3n de \u00a0 las normas constitucionales y legales que reglamentan la materia, esta Sala \u00a0 Plena concluy\u00f3 que los cargos de Magistrados de Tribunal Sala Civil, \u00a0 especializados en restituci\u00f3n de tierras, son permanentes de carrera, por tanto, \u00a0 deben adelantarse un concurso de m\u00e9ritos para su provisi\u00f3n, pertenecen a la \u00a0 jurisdicci\u00f3n ordinaria civil y, su nombramiento debe hacerse en propiedad. Aqu\u00ed, \u00a0 cabe mencionar que a esta misma conclusi\u00f3n lleg\u00f3 el Consejo Superior de la \u00a0 Judicatura, en los actos administrativos de mayo de 2013, en los cuales fijo los \u00a0 par\u00e1metros acerca de la forma en que deb\u00edan nombrarse a estos funcionarios de la \u00a0 Rama Judicial. \u00a0 \u00a0<\/p>\n<p>4.7.5. A partir de \u00a0 lo anterior, en el tema de la provisi\u00f3n de los cargos mencionados se concluye, \u00a0 por un lado, que existe claridad normativa, en tanto existe norma aplicable y, \u00a0 por el otro, que se encuentra superada la disparidad de interpretaciones que \u00a0 dieron lugar a un inicial nombramiento en provisionalidad. Por esta raz\u00f3n, la \u00a0 Corte estima que debi\u00f3 darse aplicaci\u00f3n a las normas -Acuerdo y Circular- que \u00a0 resolvieron la incertidumbre sobre la naturaleza y la forma de proveer dichos \u00a0 cargos. Vale la pena resaltar que estos actos administrativos fueron expedidos \u00a0 por la Sala Administrativa del Consejo Superior de la Judicatura, en ejercicio \u00a0 de la potestad constitucional que le asiste para reglamentar la carrera \u00a0 judicial, por ende, se presume su legalidad y surten plenos efectos hasta tanto \u00a0 no sea declarada su nulidad en la jurisdicci\u00f3n de lo contencioso administrativo. \u00a0 Resta por indicar que la presente consideraci\u00f3n adquiere mayor connotaci\u00f3n en \u00a0 raz\u00f3n a que, como qued\u00f3 demostrado, tales actos administrativos o normas son \u00a0 fieles y arm\u00f3nicas con la interpretaci\u00f3n sistem\u00e1tica que ha hecho la Corte \u00a0 Constitucional de la Constituci\u00f3n, de la ley de V\u00edctimas y Restituci\u00f3n de \u00a0 tierras y de la misma ley Estatutaria de Administraci\u00f3n de Justicia. \u00a0 \u00a0<\/p>\n<p>4.7.6. Con base en \u00a0 lo anterior, la Corte considera, en primer lugar, que la accionada debi\u00f3 aplicar \u00a0 las normas o los actos administrativos que eran pertinentes al caso concreto y \u00a0 que le resultaban vinculantes para el desempe\u00f1o de su funci\u00f3n como nominador de \u00a0 los Magistrados de Tribunal Sala Civil, especializados en restituci\u00f3n de \u00a0 tierras, de los distritos judiciales de Antioquia, Bogot\u00e1 D.C., Cali, C\u00facuta y, \u00a0 Cartagena. Tales Acuerdo y Circular son conformes con la Constituci\u00f3n, como lo \u00a0 dispuso esta Corporaci\u00f3n en la Sentencia T-319 de 2014 y como ahora lo vuelve a \u00a0 reiterar. En estos t\u00e9rminos, la Corte encuentra estructurado el defecto material \u00a0 o sustantivo que vulner\u00f3 el derecho al debido proceso administrativo de los \u00a0 accionantes. \u00a0 \u00a0<\/p>\n<p>4.8. De la extensi\u00f3n de los efectos de \u00a0 la sentencia a los dem\u00e1s Magistrados de restituci\u00f3n de tierras y \u00a0de las \u00f3rdenes \u00a0 de amparo. \u00a0 \u00a0<\/p>\n<p>4.8.1. En el \u00a0 presente proceso, la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia, \u00a0 como juez de tutela de primera instancia, orden\u00f3 la vinculaci\u00f3n de los \u00a0 Magistrados de Tribunal Superior Sala Civil, especializados en restituci\u00f3n de \u00a0 tierras, de los Distritos Judiciales de Bogot\u00e1 D.C., Cartagena, Cali y C\u00facuta, \u00a0 junto con los accionantes pertenecientes al Distrito Judicial de Antioquia. \u00a0 Ellos fueron nombrados en provisionalidad, por la entidad accionada, en \u00a0 los cargos referidos el 10 de mayo de 2012 y, tambi\u00e9n, presentaron la petici\u00f3n \u00a0 del 20 de mayo de 2013 ante la misma autoridad, solicitando que la provisi\u00f3n de \u00a0 esos cargos se hiciera en propiedad. \u00a0 \u00a0<\/p>\n<p>4.8.2. Al \u00a0 respecto, la Corte advierte que, los funcionarios vinculados al presente tr\u00e1mite \u00a0 de tutela se encuentran en situaciones an\u00e1logas \u2013tanto f\u00e1ctica como \u00a0 jur\u00eddicamente- a las de los accionantes: por (i) haber sido nombrados, en \u00a0 provisionalidad, por la Sala Plena del tribunal demandado mediante decisi\u00f3n del \u00a0 10 de mayo de 2012; (ii) en el cargo de Magistrado de Tribunal Sala Civil, \u00a0 especialidad en restituci\u00f3n de tierras; y (iii) porque su solicitud de \u00a0 nombramiento en propiedad, fue desatendida por la entidad nominadora, sin tener \u00a0 en consideraci\u00f3n los actos administrativos de la Sala Administrativa del Consejo \u00a0 Superior de la Judicatura que indicaron la forma de proveerlos. Por estas \u00a0 razones, la Corte con el fin de garantizar en condiciones de igualdad la \u00a0 protecci\u00f3n del derecho al debido proceso administrativo de este grupo de \u00a0 funcionarios, extender\u00e1 los efectos de esta providencia en la respectiva orden \u00a0 de amparo. \u00a0 \u00a0<\/p>\n<p>4.8.3. En ese sentido, la Corte revocar\u00e1 los fallos de tutela \u00a0 de ambas instancias que denegaron el amparo deprecado por los actores, para en \u00a0 su lugar, tutelar el derecho fundamental al debido proceso administrativo de los \u00a0 Magistrados de Tribunal Sala Civil, especializados en restituci\u00f3n de tierras, de \u00a0 los distritos judiciales antes mencionados. En consecuencia, (i) dejar\u00e1 sin \u00a0 efectos los actos administrativos proferidos por la Sala Plena de la Corte \u00a0 Suprema de Justicia, el primero, adoptado en sesi\u00f3n del 8 de agosto de 2013, \u00a0 comunicado el 12 de agosto del mismo a\u00f1o, mediante el cual neg\u00f3 el nombramiento \u00a0 en propiedad solicitado por los accionantes y, el segundo, adoptado en sesi\u00f3n \u00a0 del 5 de septiembre del 2013, comunicado el 18 de septiembre del mismo a\u00f1o, por \u00a0 medio del cual rechaz\u00f3 por improcedente el recurso de reposici\u00f3n presentado \u00a0 contra la negativa inicial; y (ii) ordenar\u00e1 a la Sala Plena de la Corte Suprema \u00a0 de Justicia que, en el t\u00e9rmino de los quince d\u00edas (15) siguientes a la \u00a0 notificaci\u00f3n de esta providencia, profiera los actos administrativos tendientes \u00a0 a nombrar en propiedad a los Magistrados de Tribunal Sala Civil, especializados \u00a0 en restituci\u00f3n de tierras, de los Distritos Judiciales de Cali, Cartagena, \u00a0 C\u00facuta, Bogot\u00e1 D.C. y Antioquia. \u00a0 \u00a0<\/p>\n<p>4.8.5. Por lo dicho, la consecuencia negativa de un \u00a0 vencimiento de la lista o registro de elegibles que pudiera haber ocurrido \u00a0 mientras se surt\u00eda el proceso de revisi\u00f3n por esta Corporaci\u00f3n, son inoponibles \u00a0 a los tutelantes y terceros vinculados. De no ser as\u00ed, se les infligir\u00eda un \u00a0 perjuicio mayor, haciendo nugatoria la protecci\u00f3n del derecho al debido proceso \u00a0 administrativo y desconociendo su derecho a la tutela efectiva. \u00a0 \u00a0<\/p>\n<p>III. \u00a0 CONCLUSI\u00d3N. \u00a0 \u00a0<\/p>\n<p>1. S\u00edntesis del caso. Los se\u00f1ores Vicente Landinez Lara, \u00a0 Juan Pablo Su\u00e1rez Orozco y Javier Enrique Castillo Cadena, presentaron acci\u00f3n de \u00a0 tutela contra la Sala Plena de la Corte Suprema de Justicia, por considerar \u00a0 vulnerados sus derechos fundamentales, con ocasi\u00f3n de los actos administrativos \u00a0 del 12 de agosto de 2013 y del 5 de septiembre del mismo a\u00f1o, por medio los \u00a0 cuales se neg\u00f3 la solicitud de reconsideraci\u00f3n y, rechaz\u00f3 el recurso de \u00a0 reposici\u00f3n, que fueron presentados por los accionantes para cambiar sus \u00a0 nombramientos hechos en provisionalidad, en los cargos de Magistrados Sala \u00a0 Civil, especializados en restituci\u00f3n de tierras, del Tribunal Superior de \u00a0 Distrito Judicial de Antioquia. \u00a0 \u00a0<\/p>\n<p>2. Decisi\u00f3n. La \u00a0 Corte concluye que se vulner\u00f3 el derecho al debido proceso administrativo de los \u00a0 tutelantes y de los terceros vinculados, por la configuraci\u00f3n de un defecto \u00a0 material o sustantivo. Este defecto se presenta porque el tribunal accionado, en \u00a0 condici\u00f3n de nominador, dej\u00f3 de aplicar, sin raz\u00f3n constitucional que lo \u00a0 justificara, la norma o los actos administrativos (Acuerdo y Circular), por \u00a0 medio de los cuales la Sala Administrativa del Consejo Superior de la Judicatura \u00a0 determin\u00f3 que la provisi\u00f3n de los cargos mencionados deb\u00eda hacerse en propiedad. \u00a0 \u00a0<\/p>\n<p>3. Reglas \u00a0 de decisi\u00f3n. (i) Trat\u00e1ndose de un cargo judicial de carrera, la autoridad nominadora \u00a0 debe aplicar las normas constitucionales, estatutarias y dem\u00e1s normas legales o \u00a0 reglamentarias jur\u00eddicas que disponen su creaci\u00f3n y naturaleza. (ii) La omisi\u00f3n \u00a0 injustificada de designar en propiedad en un cargo de carrera judicial, de \u00a0 car\u00e1cter permanente, a una persona, que aprob\u00f3 el respectivo concurso de m\u00e9ritos \u00a0 y que fue incluida en la lista de elegibles, la hace incursa en un defecto \u00a0 material o sustantivo que vulnera el derecho fundamental al debido proceso \u00a0 administrativo[69]. \u00a0 \u00a0<\/p>\n<p>IV. DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>La Corte Constitucional, administrando justicia en \u00a0 nombre del pueblo y por mandato de la Constituci\u00f3n, \u00a0 \u00a0<\/p>\n<p>RESUELVE: \u00a0 \u00a0<\/p>\n<p>Primero.- REVOCAR la sentencia de segunda instancia \u00a0 proferida por la Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia, el 19 \u00a0 de noviembre de 2014, confirmatoria de la sentencia de primera instancia \u00a0 proferida por la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia, el 18 \u00a0 de septiembre de 2014 que deneg\u00f3 el amparo deprecado por los accionantes. En su \u00a0 lugar, TUTELAR el derecho fundamental al debido proceso administrativo de los \u00a0 se\u00f1ores Vicente Landinez Lara, Juan Pablo Su\u00e1rez Orozco y Javier Enrique \u00a0 Castillo Cadena y de los terceros vinculados a este proceso de tutela. \u00a0 \u00a0<\/p>\n<p>Segundo.- DEJAR SIN EFECTOS los actos administrativos \u00a0 proferidos por la Sala Plena de la Corte Suprema de Justicia, el primero de \u00a0 ellos, adoptado en sesi\u00f3n del 8 de agosto de 2013, comunicado el 12 de agosto \u00a0 del mismo a\u00f1o, mediante el cual neg\u00f3 el nombramiento en propiedad solicitado por \u00a0 los accionantes y, el segundo, adoptado en sesi\u00f3n del 5 de septiembre del 2013, \u00a0 comunicado el 18 de septiembre del mismo a\u00f1o, por medio del cual rechaz\u00f3 por \u00a0 improcedente el recurso de reposici\u00f3n presentado contra la negativa inicial. \u00a0 \u00a0<\/p>\n<p>Tercero.- ORDENAR a la Sala Plena de la Corte Suprema \u00a0 de Justicia que, en el t\u00e9rmino de los quince (15) d\u00edas siguientes a la \u00a0 notificaci\u00f3n de esta providencia, profiera los actos administrativos tendientes \u00a0 a nombrar en propiedad a los Magistrados de Tribunal Sala Civil, especializados \u00a0 en restituci\u00f3n de tierras, de los Distrito Judiciales de Cali, Cartagena, \u00a0 C\u00facuta, Bogot\u00e1 D.C. y Antioquia. \u00a0 \u00a0 \u00a0<\/p>\n<p>L\u00cdBRESE por Secretar\u00eda General la comunicaci\u00f3n prevista en el \u00a0 art\u00edculo 36 del Decreto 2919 de 1991. \u00a0 \u00a0<\/p>\n<p>C\u00f3piese, notif\u00edquese, \u00a0 comun\u00edquese, ins\u00e9rtese en la Gaceta de la Corte Constitucional y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>MARIA VICTORIA CALLE \u00a0 CORREA \u00a0 \u00a0<\/p>\n<p>Presidenta \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>MYRIAM \u00c1VILA ROLD\u00c1N \u00a0 \u00a0<\/p>\n<p>Magistrada (E) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>MAURICIO GONZ\u00c1LEZ \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0CUERVO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>LUIS GUILLERMO \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0GUERRERO PEREZ \u00a0 \u00a0<\/p>\n<p>Magistrado\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>GABRIEL EDUARDO \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0MENDOZA MARTELO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>Con aclaraci\u00f3n de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0voto \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>GLORIA STELLA ORTIZ \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0DELGADO \u00a0 \u00a0<\/p>\n<p>Magistrada \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>JORGE IGNACIO \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0PRETELT CHALJUB \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>ALBERTO ROJAS R\u00cdOS \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>JORGE IV\u00c1N PALACIO \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0PALACIO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>Ausente con \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0permiso \u00a0\u00a0<\/p>\n<p>MARTHA VICTORIA \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0S\u00c1CHICA M\u00c9NDEZ \u00a0 \u00a0<\/p>\n<p>Secretaria General \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>ACLARACI\u00d3N DE VOTO DEL MAGISTRADO \u00a0 \u00a0<\/p>\n<p>GABRIEL EDUARDO MENDOZA MARTELO \u00a0 \u00a0<\/p>\n<p>A LA SENTENCIA SU553\/15 \u00a0 \u00a0<\/p>\n<p>MAGISTRADOS ESPECIALIZADOS EN RESTITUCION DE \u00a0 TIERRAS Y JUECES CIVILES DEL CIRCUITO ESPECIALIZADOS EN RESTITUCION DE TIERRAS-Nombramientos \u00a0 en provisionalidad no podr\u00edan generar derechos de estabilidad o de \u00a0 carrera distintos a los que ya se tienen sobre otros cargos, una vez vencido el \u00a0 l\u00edmite temporal para el cual fueron creados (Aclaraci\u00f3n de voto) \u00a0 \u00a0<\/p>\n<p>Referencia: \u00a0 Expediente T-4.789.181. Revisi\u00f3n de las Sentencias proferidas por la Sala de \u00a0 Casaci\u00f3n Laboral de la Corte Suprema de Justicia, del 19 de noviembre de 2014, \u00a0 que confirm\u00f3 la Sentencia de la Sala de Casaci\u00f3n Civil de la Corte Suprema de \u00a0 Justicia, del 18 de septiembre de 2014. \u00a0 \u00a0<\/p>\n<p>Accionantes: \u00a0 Vicente Landinez Lara, Juan Pablo Su\u00e1rez Orozco y Javier Enrique Castillo \u00a0 Cadena. Accionado: Sala Plena de la Corte Suprema de Justicia. \u00a0 \u00a0<\/p>\n<p>MAURICIO GONZ\u00c1LEZ \u00a0 CUERVO \u00a0 \u00a0<\/p>\n<p>Comparto la decisi\u00f3n de mayor\u00eda con las precisiones que a continuaci\u00f3n, \u00a0 brevemente, expongo: \u00a0 \u00a0<\/p>\n<p>Los \u00a0 hechos que dieron lugar a la acci\u00f3n de tutela, objeto de estudio en esta \u00a0 oportunidad, en s\u00edntesis, dan cuenta de lo siguiente: \u00a0 \u00a0<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Mediante el \u00a0 Acuerdo PSAA-12-9268 de 2012, la Sala Administrativa del Consejo Superior de la \u00a0 Judicatura cre\u00f3 los despachos de Magistrados en Salas Civiles, especializados en \u00a0 restituci\u00f3n de tierras, en los Tribunales Superiores de Distrito Judicial de \u00a0 Antioquia, Bogot\u00e1 D.C., Cali, Cartagena y C\u00facuta. \u00a0 \u00a0<\/p>\n<p>2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Para darle \u00a0 efectividad a la medida, el Consejo Superior de la Judicatura present\u00f3 ante la \u00a0 Corte Suprema de Justicia las listas de candidatos tomadas del Registro Nacional \u00a0 de Elegibles vigente. \u00a0 \u00a0<\/p>\n<p>3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Antes de que se \u00a0 realizaran dichos nombramientos la Sala de Gobierno de la Corte, le solicit\u00f3 a \u00a0 la Sala Administrativa que aclarara el car\u00e1cter de dichos cargos, y esta \u00a0 absolvi\u00f3 dicha inquietud, de una forma &#8220;no muy clara&#8221;, manifestando que estos \u00a0 eran de car\u00e1cter permanente. \u00a0 \u00a0<\/p>\n<p>4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0La Corte Suprema \u00a0 de Justicia procedi\u00f3 entonces a realizar los nombramientos, en provisionalidad, \u00a0 argumentando que el Acuerdo que cre\u00f3 los cargos no especific\u00f3 si eran de carrera \u00a0 o si se creaban en provisionalidad, dado que la Ley 1448 de 2011 \u00a0 &#8220;por la cual se dictan medidas de atenci\u00f3n, asistencia y reparaci\u00f3n integral a \u00a0 las v\u00edctimas del conflicto armado interno y se dictan otras disposiciones&#8221;, \u00a0 tiene una vigencia de 10 a\u00f1os. \u00a0 \u00a0<\/p>\n<p>5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Los actores \u00a0 presentaron una petici\u00f3n ante la Corte Suprema a objeto de que reconsiderada su \u00a0 decisi\u00f3n sobre el tipo de nombramiento mediante el cual hab\u00eda provisto los \u00a0 cargos y que para ello tuviera en cuenta que la Sala Administrativa del Consejo \u00a0 Superior de la Judicatura hab\u00eda aprobado los conceptos emitidos por la Unidad de \u00a0 Carrera Judicial, en el sentido de que los cargos en cuesti\u00f3n son permanentes y \u00a0 de carrera por lo que deb\u00edan designarse en propiedad con base en las \u00a0 correspondientes listas de elegibles. Sin embargo, dicha solicitud fue resuelta \u00a0 y reiterada al desatar los recursos, de forma negativa. \u00a0 \u00a0<\/p>\n<p>En esta ocasi\u00f3n la Sala Plena opt\u00f3 por amparar el derecho fundamental al debido \u00a0 proceso administrativo de los actores, decisi\u00f3n que comparto plenamente, sin \u00a0 embargo, a mi juicio, considero necesario aclarar que, si bien la orden \u00a0 constitucional consisti\u00f3 en que la Sala Plena de la Corte Suprema de Justicia \u00a0 profiriera los actos administrativos tendientes a nombrar en propiedad a los \u00a0 Magistrados de Tribunal Sala Civil, especializados en restituci\u00f3n de tierras, de \u00a0 los Distritos Judiciales de Cali, Cartagena, C\u00facuta, Bogot\u00e1 D.C. y Antioquia, \u00a0 ello no implica que dichos nombramientos tengan el car\u00e1cter de permanentes, \u00a0 puesto que el acto administrativo que cre\u00f3 los cargos estableci\u00f3 un l\u00edmite \u00a0 temporal de 10 a\u00f1os para el ejercicio y existencia de los mismos, lo cual \u00a0 constituye una realidad jur\u00eddica inobjetable que, de antemano, deja ver a \u00a0 quienes aspiren a dichos cargos cu\u00e1les son las condiciones de duraci\u00f3n o plazo a \u00a0 las que queda sujeta su designaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>De \u00a0 manera que los nombramientos que bajo los indicados par\u00e1metros se realicen, a\u00fan \u00a0 con personas que hagan parte de las listas de elegibles, lo cual, a mi juicio, \u00a0 en principio, es lo que corresponde hacer, pues se escoger\u00edan personas con \u00a0 verificada idoneidad, no podr\u00edan generar derechos de estabilidad o de carrera \u00a0 distintos a los que ya se tienen sobre otros cargos, una vez vencido el l\u00edmite \u00a0 temporal para el cual fueron creados, salvo que otra ley prorrogue o vuelva \u00a0 permanente su duraci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Fecha ut supra, \u00a0 \u00a0<\/p>\n<p>GABRIEL EDUARDO \u00a0 MENDOZA MARTELO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>[1] La expedici\u00f3n del acto administrativo que cre\u00f3 los cargos se produjo \u00a0 previo concepto favorable emitido por la Comisi\u00f3n Interinstitucional de la Rama \u00a0 Judicial (Acuerdo No. 4 del 23 de febrero de 2012) (folio 21 cuaderno No.2). En \u00a0 adelante, siempre que se cite un folio se entender\u00e1 que hace parte del cuaderno \u00a0 principal, salvo que se haga manifestaci\u00f3n en contrario.\u00a0 \u00a0 \u00a0<\/p>\n<p>[2] Acuerdos PSAA12-9316, 9317, 9319 y 9320 del 23 de marzo de 2012, \u00a0 expedidos por la Sala Administrativa del Consejo Superior de la Judicatura \u00a0 (folios 309 y 310) (folios 24 cuaderno No.2) \u00a0 \u00a0<\/p>\n<p>[3] Seg\u00fan consta en la copia del acta No.19 de la sesi\u00f3n ordinaria \u00a0 celebrada por la Sala Plena de la Corte Suprema de Justicia el 10 de mayo de \u00a0 2012 (folio 55). En dicha acta se dej\u00f3 constancia de que: \u201cla Sala Civil \u00a0 analiz\u00f3 el tema y arrib\u00f3 a la conclusi\u00f3n de que si bien no hay un concurso \u00a0 espec\u00edfico para la provisi\u00f3n de los cargos creados, si hay un registro de \u00a0 elegibles, adem\u00e1s de unas listas que remiti\u00f3 la Sala Administrativa de las \u00a0 cuales se deben designar los Magistrados de Restituci\u00f3n de Tierras y que dichos \u00a0 nombramientos deben serlo en provisionalidad, por la temporalidad de la Ley 1448 \u00a0 de 2011, tal como ocurre con la Ley de Justicia y Paz\u201d. \u00a0 \u00a0<\/p>\n<p>[4] Seg\u00fan consta en la copia del derecho de petici\u00f3n presentado por el \u00a0 se\u00f1or Vicente Landinez Lara y otros, ante la Presidenta de la Sala de Casaci\u00f3n \u00a0 Civil de la Corte Suprema de Justicia, el 20 de mayo de 2013 (folios 67 a 71). \u00a0 \u00a0<\/p>\n<p>[5] Seg\u00fan consta en las copias del oficio de remisi\u00f3n, del 31 de mayo de \u00a0 2013, y de la Circular PSAC13-14 del 27 de mayo de 2013, expedida por la Sala \u00a0 Administrativa del C.S.J. (folios 72 y 73). \u00a0 \u00a0<\/p>\n<p>[6] La entidad accionada le inform\u00f3 a los peticionarios que, en sesi\u00f3n \u00a0 plenaria del 8 de agosto de 2013, estudi\u00f3 el derecho de petici\u00f3n y, en \u00a0 consecuencia, resolvi\u00f3 mantener la decisi\u00f3n adoptada en la sesi\u00f3n plenaria de \u00a0 mayo 10 de 2012, seg\u00fan la cual \u201c\u2026los nombramientos deben serlo en \u00a0 provisionalidad, solicitando a la Sala Administrativa convocar a un concurso de \u00a0 m\u00e9ritos espec\u00edfico para la especialidad.\u201d (folios 74 y 75). \u00a0 \u00a0<\/p>\n<p>[7] Folios 63 a 65 del cuaderno No.2. \u00a0 \u00a0<\/p>\n<p>[8] Seg\u00fan consta en la copia del acto del 5 de septiembre de 2013, \u00a0 proferido por la Sala Plena de la Corte Suprema de Justicia (folios 78 y 79). \u00a0 Afirman los accionantes que fueron notificados de esta decisi\u00f3n el 9 de octubre \u00a0 de 2013 (folio 4). \u00a0 \u00a0<\/p>\n<p>[9] Para tal efecto, cit\u00f3 las Sentencias T-843 de 2009, SU-613 de 2002 y \u00a0 T-947 de 2012. \u00a0 \u00a0<\/p>\n<p>[10] Folios 70 y 71 cuaderno No.2. \u00a0 \u00a0<\/p>\n<p>[12] Folios 243 a 247. \u00a0 \u00a0<\/p>\n<p>[13] Folios 189 y 190. \u00a0 \u00a0<\/p>\n<p>[14] Folios 181 a 187. \u00a0 \u00a0<\/p>\n<p>[15] Folios 216 a 219. \u00a0 \u00a0<\/p>\n<p>[16] Folios 235 a 241. \u00a0 \u00a0<\/p>\n<p>[17] Folios 272 a 275. \u00a0 \u00a0<\/p>\n<p>[18] Folios 320 a 334. \u00a0 \u00a0<\/p>\n<p>[19] Folio 413. \u00a0 \u00a0<\/p>\n<p>[20] Folios 415 a 418. \u00a0 \u00a0<\/p>\n<p>[21] Mediante auto del 11 de febrero de 2014, la Sala Civil de la Corte \u00a0 Suprema de Justicia admiti\u00f3 la acci\u00f3n de tutela y orden\u00f3 notificar a la parte \u00a0 accionada y vincul\u00f3 a terceros interesados. La Sala Laboral de la misma \u00a0 Corporaci\u00f3n, mediante providencia del 30 de julio de 2014, declar\u00f3 la nulidad de \u00a0 todo lo actuado a partir del 11 de febrero de 2014, en raz\u00f3n a que dentro del \u00a0 tr\u00e1mite se omiti\u00f3 vincular a las dem\u00e1s personas que hab\u00edan sido nombrados por la \u00a0 accionada, como Magistrados de Tribunal Superior, Sala Civil, especialidad en \u00a0 restituci\u00f3n de tierras, el 10 de mayo de 2012. \u00a0 \u00a0<\/p>\n<p>[22] El se\u00f1or Puno Alirio Correal Beltr\u00e1n solicit\u00f3 la \u00a0 nulidad desde el auto de 9 de septiembre de 2014, fundado en el hecho de haberse \u00a0 emitido la sentencia de primera instancia, sin haberse resuelto primero su \u00a0 solicitud de remitir el proceso por competencia ante el Consejo Superior de la \u00a0 Judicatura, autoridad ante la cual se present\u00f3 en principio la acci\u00f3n de tutela. \u00a0 Al respecto, el Conjuez Ponente Rafael H. Gamboa Serrano, mediante providencia \u00a0 del 29 de septiembre de 2014, rechaz\u00f3 de plano dicha nulidad de conformidad con \u00a0 el art\u00edculo 143 de C. de P.C., toda vez que no se basa en ninguna de las \u00a0 causales previstas en el ordenamiento procesal. Posteriormente, el se\u00f1or Correal \u00a0 solicit\u00f3 que se revocara la anterior decisi\u00f3n y que se diera tr\u00e1mite a su \u00a0 solicitud de nulidad, pero la entidad accionada neg\u00f3 lo pedido mediante \u00a0 providencia del 3 de octubre de 2014 (folio 498).\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>[23] Folios 2 a 4 del cuaderno de pruebas. \u00a0 \u00a0<\/p>\n<p>[24] En Auto \u00a0 del 16 de abril de 2015 de la Sala de Selecci\u00f3n de tutela No. 4 de la Corte \u00a0 Constitucional, se dispuso la revisi\u00f3n de las providencias en cuesti\u00f3n y se \u00a0 procedi\u00f3 a su reparto. \u00a0 \u00a0<\/p>\n<p>[25] Constituci\u00f3n Pol\u00edtica, art\u00edculo 86. \u00a0 \u00a0<\/p>\n<p>[26] En la \u00a0 sentencia T-900 de 2004, esta Corporaci\u00f3n sobre el requisito de inmediatez, \u00a0 se\u00f1al\u00f3: \u201c(&#8230;) la jurisprudencia constitucional tiene establecido que el \u00a0 presupuesto de la inmediatez constituye un requisito de procedibilidad de la \u00a0 tutela, de tal suerte que la acci\u00f3n debe ser interpuesta dentro de un plazo \u00a0 razonable, oportuno y justo. Con tal exigencia se pretende evitar que este \u00a0 mecanismo de defensa judicial se emplee como herramienta que premia la desidia, \u00a0 negligencia o indiferencia de los actores, o se convierta en un factor de \u00a0 inseguridad jur\u00eddica. \u00a0 \u00a0 \u00a0<\/p>\n<p>\u201cEsta condici\u00f3n est\u00e1 \u00a0 contemplada en el art\u00edculo 86 de la Carta Pol\u00edtica como una de las \u00a0 caracter\u00edsticas de la tutela, cuyo objeto es precisamente la protecci\u00f3n \u00a0 inmediata de los derechos constitucionales fundamentales de toda persona, cuando \u00a0 quiera que \u00e9stos resulten vulnerados o amenazados por la acci\u00f3n o la omisi\u00f3n de \u00a0 cualquier autoridad p\u00fablica o de los particulares en los casos que establezca la \u00a0 ley. As\u00ed, pues, es inherente a la acci\u00f3n de tutela la protecci\u00f3n actual, \u00a0 inmediata y efectiva de aquellos derechos.\u201d \u00a0 \u00a0<\/p>\n<p>[27] Sentencia SU-446 de 1999, en la cual se hizo un recuento y \u00a0 unificaci\u00f3n de la jurisprudencia hasta entonces existente en torno a este tema. \u00a0 \u00a0<\/p>\n<p>[28]\u00a0 Ib\u00eddem. \u00a0 \u00a0<\/p>\n<p>[29] Respecto de este requisito fundamental de procedencia \u00a0 de la acci\u00f3n de tutela, la Sala Plena de la Corte Constitucional, en la \u00a0 Sentencia SU-961 de 1999, estableci\u00f3: \u201cla razonabilidad de este plazo est\u00e1 \u00a0 determinada por la finalidad misma de la tutela, que debe ser ponderada en cada \u00a0 caso concreto.\u00a0 De acuerdo con los hechos, entonces, el juez est\u00e1 encargado \u00a0 de establecer si la tutela se interpuso dentro de un tiempo prudencial y \u00a0 adecuado, de tal modo que no se vulneren derechos de terceros. Si bien el \u00a0 t\u00e9rmino para interponer la acci\u00f3n de tutela no es susceptible de establecerse de \u00a0 antemano de manera afirmativa, el juez est\u00e1 en la obligaci\u00f3n de verificar cu\u00e1ndo \u00a0 \u00e9sta no se ha interpuesto de manera razonable, impidiendo que se convierta en \u00a0 factor de inseguridad, que de alguna forma afecte los derechos fundamentales de \u00a0 terceros, o que desnaturalice la acci\u00f3n. En jurisprudencia reiterada, la Corte \u00a0 ha determinado que la acci\u00f3n de tutela se caracteriza por su \u2018inmediatez\u2019. (&#8230;) \u00a0 Si el elemento de la inmediatez es consustancial a la protecci\u00f3n que la acci\u00f3n \u00a0 brinda a los derechos de los ciudadanos, ello implica que debe ejercerse de \u00a0 conformidad con tal naturaleza.\u00a0 Esta condiciona su ejercicio a trav\u00e9s de \u00a0 un deber correlativo: la interposici\u00f3n oportuna y justa de la acci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>[30] SU-961 de 1999. \u00a0 \u00a0<\/p>\n<p>[31] SU-961 de 1999 y\u00a0T-743 de \u00a0 2008. \u00a0 \u00a0<\/p>\n<p>[32] Sentencia T-584\/11,\u00a0T-158 de 2006 \u00a0 y T-792 de 2007, entre otras. \u00a0 \u00a0<\/p>\n<p>[33] De acuerdo con el art\u00edculo 6\u00b0 del Decreto 2591 de 1991, \u201c[l]a acci\u00f3n \u00a0 de tutela no proceder\u00e1: 1.- Cuando existan otros recursos o medios de defensa \u00a0 judiciales, salvo que aquella se utilice como mecanismo transitorio para evitar \u00a0 un perjuicio irremediable. La existencia de dichos medios ser\u00e1 aplicada en \u00a0 concreto, en cuanto a su eficacia, atendiendo las circunstancias en que se \u00a0 encuentra el solicitante\u201d \u00a0 \u00a0<\/p>\n<p>[34] Corte Constitucional\u00a0 Sentencias T-514 de 2003, T-435 de 2005 y \u00a0 T-368 de 2008. \u00a0 \u00a0<\/p>\n<p>[35] Sentencia T-629 de 2008. \u00a0 \u00a0<\/p>\n<p>[36] Respecto a la procedencia de la acci\u00f3n de tutela \u00a0 contra actos administrativos, la Corte en la sentencia T-1231 de 2008 se\u00f1al\u00f3: \u00a0\u201cCuando se trata de solicitudes de amparo relacionadas con actos \u00a0 administrativos, esta Corporaci\u00f3n ha precisado la impertinencia de la acci\u00f3n del \u00a0 amparo constitucional. Ello porque la v\u00eda para impugnar dichos actos es la \u00a0 contencioso administrativa y dado el car\u00e1cter subsidiario de la tutela \u00e9sta \u00a0 resultar\u00eda improcedente, excepto como mecanismo transitorio para evitar un \u00a0 perjuicio irremediable\u201d. \u00a0 \u00a0<\/p>\n<p>[37] Reiterado en la Sentencia SU-086 de 1999. \u00a0 \u00a0<\/p>\n<p>[38] En la Sentencia T-090 de 2013 se establece que esta\u00a0subregla\u00a0de procedencia excepcional de la acci\u00f3n de \u00a0 tutela la contempla el art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica. \u00a0 \u00a0<\/p>\n<p>[39] Ver la Sentencia T-225 de 1993. \u00a0 \u00a0<\/p>\n<p>[40] Para tal efecto, cit\u00f3 las Sentencias T-843 de 2009, SU-613 de 2002 y \u00a0 T-947 de 2012. \u00a0 \u00a0<\/p>\n<p>[42] En la Sentencia SU-913 de 2009, la Corte revis\u00f3 acciones de tutela \u00a0 en las cuales, como elemento com\u00fan, se alegaba la inaplicaci\u00f3n parcial de las \u00a0 listas de elegibles que resultaron del concurso de m\u00e9ritos convocado mediante el \u00a0 Acuerdo 01 de 2006, para la provisi\u00f3n de cargos de notarios en\u00a0 propiedad y \u00a0 acceso a la carrera notarial, como consecuencia de la suspensi\u00f3n\u00a0 \u00a0 provisional ordenada\u00a0 en el curso de la acci\u00f3n popular 0413-97 -para \u00a0 algunos participantes- de cinco puntos que el art\u00edculo 4 de la Ley 588 de 2000 \u00a0 otorga a la autor\u00eda de obras en derecho. Medida cautelar que torn\u00f3 a\u00a0definitiva \u00a0 mediante la sentencia de 13 de julio de 2009, proferida por el Tribunal \u00a0 Administrativo del Tolima. \u00a0 \u00a0<\/p>\n<p>[43] Sentencia T-175 de 1997. \u00a0 \u00a0<\/p>\n<p>[44] Resoluci\u00f3n PSAR11-601 del 17 de junio de 2011, de la Sala \u00a0 Administrativa del Consejo Superior de la Judicatura. \u00a0 \u00a0<\/p>\n<p>[45] Folio 3 del cuaderno No.2. \u00a0 \u00a0<\/p>\n<p>[46] Acuerdo No.PSAA13-9939 de junio 25 de 2013, expedido por la \u00a0 Sala Administrativa del Consejo Superior de la Judicatura, \u201cpor medio del \u00a0 cual se adelanta el proceso de selecci\u00f3n y se convoca al concurso de m\u00e9ritos \u00a0 para la provisi\u00f3n de los cargos de Funcionarios de la Rama Judicial\u201d (folios \u00a0 70 y 71 del cuaderno No.2). \u00a0 \u00a0<\/p>\n<p>[47] Supra I. 1.2.7. \u00a0 \u00a0<\/p>\n<p>[48] La Corte Constitucional en la Sentencia T-076 de 2011, se dio a la \u00a0 tarea de adaptar las causales de procedibilidad de la acci\u00f3n de tutela contra \u00a0 providencias judiciales al lenguaje y caracter\u00edsticas propias del \u00e1mbito \u00a0 administrativo. El empleo de esta metodolog\u00eda fue reiterado en la Sentencia \u00a0 T-325 de 2012. \u00a0 \u00a0<\/p>\n<p>[49] Cfr. Sentencias T-076 de 2011 y T-214 \u00a0 de 2004. \u00a0 \u00a0<\/p>\n<p>[50] Sentencia C- 588 de 2009. \u00a0 \u00a0<\/p>\n<p>[51] Sentencia C-671 de 2001. \u00a0 \u00a0<\/p>\n<p>[52] Sentencia C-315 de 2007. \u00a0 \u00a0<\/p>\n<p>[53] Sentencia C-101 de 2013. \u00a0 \u00a0<\/p>\n<p>[54] En las Sentencias T-569 de 2011, \u00a0 C-319 y T-502 de 2010, C-588 de 2009, C-901 de 2008, entre otras, la \u00a0 Corte ha venido reiterando que el\u00a0m\u00e9rito\u00a0y el\u00a0concurso p\u00fablico\u00a0son los dos pilares fundamentales de la carrera \u00a0 administrativa dentro de la Carta Pol\u00edtica de 1991.\u00a0En virtud del\u00a0m\u00e9rito\u00a0se pretende que las capacidades,\u00a0 cualidades y \u00a0 eficacia del aspirante sean los factores determinantes \u201cpara el \u00a0 acceso, permanencia y retiro del empleo p\u00fablico.\u201d (C-315 de 2007).\u00a0Por su parte, el\u00a0concurso p\u00fablico\u00a0es \u00a0 el mecanismo para establecer el\u00a0m\u00e9rito, \u00a0 ya que aquel est\u00e1 exclusivamente dirigido a comprobar \u201clas calidades \u00a0 acad\u00e9micas, la experiencia y las competencias requeridas para el desempe\u00f1o de \u00a0 los empleos.\u201d(C-112 de 2005).\u00a0La Corte ha manifestado que el concurso p\u00fablico debe \u00a0 ser comprensivo de \u201ctodos y cada uno de los factores que deben reunir \u00a0 los candidatos a ocupar un cargo en la administraci\u00f3n p\u00fablica\u201d, incluidos aquellos factores en los cuales \u201cla \u00a0 calificaci\u00f3n meramente objetiva es imposible\u201d, \u00a0 ya que aquello garantiza la erradicaci\u00f3n de cualquier margen de subjetividad en \u00a0 la escogencia del concursante. \u00a0 \u00a0<\/p>\n<p>[55] Al respecto consultar Sentencia C-532 \u00a0 de 2006 y Sentencia C-553 de 2007. \u00a0 \u00a0<\/p>\n<p>[56] El art\u00edculo 156 de la Ley 270 de \u00a0 1996, establece que la carrera judicial debe basarse en\u00a0el car\u00e1cter profesional de funcionarios y \u00a0 empleados, en la eficacia de su gesti\u00f3n, en la garant\u00eda de igualdad, en las \u00a0 posibilidades de acceso a la funci\u00f3n para todos los ciudadanos aptos al efecto y \u00a0 en la consideraci\u00f3n del m\u00e9rito como fundamento principal para el ingreso, la \u00a0 permanencia y la promoci\u00f3n en el servicio. \u00a0 \u00a0<\/p>\n<p>[57] En la Sentencia C-713 de 2008, reiterada en la C-532 de 2013, la \u00a0 Corte se\u00f1al\u00f3: \u201cAs\u00ed mismo, la norma dispone que \u201clos \u00a0 jueces de descongesti\u00f3n tendr\u00e1n la competencia territorial y material espec\u00edfica \u00a0 que les se\u00f1ale el acto de su creaci\u00f3n\u201d. Los jueces de descongesti\u00f3n no son cargos permanentes y por tanto no \u00a0 forman parte de la estructura misma de la administraci\u00f3n de justicia. Son cargos \u00a0 creados de manera transitoria por el Consejo Superior de la Judicatura, dentro \u00a0 de la facultad prevista en el art\u00edculo 257-2 de la Constituci\u00f3n y de conformidad \u00a0 con las pol\u00edticas y programas de descongesti\u00f3n judicial establecidos por dicho \u00a0 organismo. (\u2026) \u00a0Ahora bien, es cierto que los jueces de descongesti\u00f3n tienen \u00a0 vocaci\u00f3n de transitoriedad (\u2026). Sin embargo, la Corte quiere llamar la atenci\u00f3n, \u00a0 con especial rigor, para dejar en claro que en virtud de los principios \u00a0 constitucionales de transparencia e igualdad, y del m\u00e9rito como criterio de \u00a0 acceso a la funci\u00f3n p\u00fablica, su designaci\u00f3n hace inexcusable tomar en cuenta y \u00a0 respetar el orden de las listas de elegibles, conformadas por quienes han \u00a0 agotado todas las etapas del concurso de m\u00e9rito y se encuentran a la espera de \u00a0 su nombramiento definitivo. S\u00f3lo de esta manera la creaci\u00f3n de jueces de \u00a0 descongesti\u00f3n es compatible con los principios que rigen la funci\u00f3n p\u00fablica y la \u00a0 designaci\u00f3n de los jueces, en particular el m\u00e9rito. \u00a0 \u00a0<\/p>\n<p>[58] Ley 975 de 2005 \u201cpor la cual se \u00a0 dicta disposiciones para la reincorporaci\u00f3n de miembros de grupos armados \u00a0 organizados al margen de la ley, que contribuyan de manera efectiva a la \u00a0 consecuci\u00f3n de la paz nacional y se dictan otras disposiciones para acuerdos \u00a0 humanitarios\u201d \u00a0 \u00a0<\/p>\n<p>[59] Sentencia SU-539 de 2012. \u00a0 \u00a0<\/p>\n<p>[60] Constituci\u00f3n Pol\u00edtica, art\u00edculo 150, numeral 2, corresponde al \u00a0 Congreso la funci\u00f3n de \u201cExpedir las leyes que regir\u00e1n el ejercicio de las \u00a0 funciones p\u00fablicas y la prestaci\u00f3n de los servicios p\u00fablicos\u201d. \u00a0 \u00a0<\/p>\n<p>[61] \u00a0 Ver, entre otras, las sentencias C-307 de 2004, C-384 de 2003 y C-805 de 2001. \u00a0 \u00a0<\/p>\n<p>[62] Ley 1448 de 2011, \u201cART\u00cdCULO 119. \u00a0 CREACI\u00d3N DE CARGOS. El Consejo Superior de la Judicatura, crear\u00e1 los cargos de \u00a0 Magistrados de los Tribunales Superiores y Jueces Civiles del Circuito, \u00a0 especializados en restituci\u00f3n de tierras, de conformidad con el numeral 5 del \u00a0 art\u00edculo 85 de la Ley 270 de 1996 y normas concordantes. El Consejo Superior de \u00a0 la Judicatura crear\u00e1 los cargos de otros funcionarios que sean requeridos para \u00a0 el cumplimiento de esta Ley. La creaci\u00f3n de los cargos a que se refiere este \u00a0 art\u00edculo se har\u00e1 en forma gradual y progresiva, acorde con las necesidades del \u00a0 servicio. (\u2026)\u201d \u00a0 \u00a0<\/p>\n<p>[63] El art\u00edculo 1\u00b0 del Acuerdo PSAA12-9268, \u00a0 del 24 de febrero de 2012, \u201cpor el cual se crean en el territorio nacional \u00a0 unos Despachos de Magistrado en Salas Civiles, especializados en restituci\u00f3n de \u00a0 tierras\u201d, dispone: \u201cCreaci\u00f3n de Despachos. Crear, a partir del 9 de abril \u00a0 de 2012, una (1) Sala Civil, especializada en restituci\u00f3n de tierras, en \u00a0 los Tribunales Superiores de los Distritos Judiciales de Bogot\u00e1, Cali, \u00a0 Cartagena, C\u00facuta y Antioquia.\u201d (subrayado fuera del original) (folio 22 del \u00a0 cuaderno No.2) \u00a0 \u00a0<\/p>\n<p>[64] El par\u00e1grafo del art\u00edculo 1\u00ba del Acuerdo \u00a0 No.PSAA13-9866, del 13 de marzo de 2013, se\u00f1ala: \u201cPrecisar que los cargos de \u00a0 Magistrados especializados en restituci\u00f3n de tierras hace parte de las Salas \u00a0 Civiles del respectivo Tribunal Superior de Distrito Judicial. En ese sentido, \u00a0 cuando en los Acuerdos expedidos con anterioridad se emplee la expresi\u00f3n \u201csala \u00a0 civil especializada\u201d, se entender\u00e1 que hace referencia a la Sala Fija de \u00a0 Decisi\u00f3n especializada conformada por los Magistrados especializados en \u00a0 restituci\u00f3n de tierras\u201d. \u00a0 \u00a0<\/p>\n<p>[65] La Circular PSAC13-14 del 22 de mayo \u00a0 de 2013, literalmente se\u00f1ala: \u201c(\u2026) todos los cargos para el ejercicio de \u00a0 restituci\u00f3n de tierras se crearon con car\u00e1cter permanente y surtieron todo el \u00a0 tr\u00e1mite, incluido el concepto previo emitido por la Comisi\u00f3n Interinstitucional \u00a0 de la Rama Judicial, en el entendido de que la asignaci\u00f3n por 10 a\u00f1os hace \u00a0 referencia a la funci\u00f3n de restituci\u00f3n de tierras. \u00a0 \u00a0\u00a0<\/p>\n<p>Por ello, \u00a0 esta Sala Administrativa en sesi\u00f3n del 23 de agosto de 2012 trat\u00f3 el tema y \u00a0 dispuso, que trat\u00e1ndose entonces de cargos creados con car\u00e1cter permanente en la \u00a0 jurisdicci\u00f3n ordinaria, a pesar de que la ley se\u00f1ala como t\u00e9rmino de vigencia de \u00a0 la misma, el de diez a\u00f1os, ello no afecta el car\u00e1cter permanente de dichos \u00a0 empleos. Es decir, reiter\u00f3 la Sala Administrativa que los cargos de jueces, \u00a0 magistrados y empleados, creados en virtud de la Ley 1448 de 2011, son cargos de \u00a0 carrera y por lo tanto su nombramiento debe ser en propiedad, los cuales, una \u00a0 vez vencido el t\u00e9rmino citado deben integrarse y continuar en la especialidad \u00a0 civil. \u00a0 \u00a0<\/p>\n<p>Por lo \u00a0 tanto, dichos cargos deben ser provistos en propiedad de los registro de \u00a0 elegibles vigentes y en ese sentido, corresponde a la autoridad nominadora \u00a0 proveerlos en la forma indicada\u201d. \u00a0 \u00a0<\/p>\n<p>[66] Cfr. Sentencia T-319 de 2014. \u00a0 \u00a0<\/p>\n<p>[67] Ver Sentencias T-076 de 2011, T-325 de 2012, entre otras. \u00a0 \u00a0<\/p>\n<p>[68] Supra II. 4.3. \u00a0 \u00a0<\/p>\n<p>[69] Sentencia T-319 de 2014.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0SU553-15 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 Sentencia SU553\/15 \u00a0 \u00a0 (Bogot\u00e1, D.C., 27 \u00a0 de agosto) \u00a0 \u00a0 ACCION DE TUTELA CONTRA \u00a0 PROVIDENCIAS JUDICIALES-Requisitos generales y especiales de procedibilidad \u00a0 \u00a0 ACCION DE TUTELA FRENTE A ACTOS \u00a0 ADMINISTRATIVOS EN MATERIA DE CONCURSO DE MERITOS-Procedencia excepcional \u00a0 para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[],"class_list":["post-22380","post","type-post","status-publish","format-standard","hentry","category-sentencias-de-unificacion-2015"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/22380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=22380"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/22380\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=22380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=22380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=22380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}