{"id":22653,"date":"2024-06-26T17:34:15","date_gmt":"2024-06-26T17:34:15","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/06\/26\/t-341-15\/"},"modified":"2024-06-26T17:34:15","modified_gmt":"2024-06-26T17:34:15","slug":"t-341-15","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-341-15\/","title":{"rendered":"T-341-15"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-341-15 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia T-341\/15 \u00a0 \u00a0<\/p>\n<p>PENSION DE JUBILACION Y PENSION COMPARTIDA-Naturaleza jur\u00eddica \u00a0 \u00a0<\/p>\n<p>COMPARTIBILIDAD PENSIONAL-Finalidad \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA PARA EL RECONOCIMIENTO DE ACREENCIAS PENSIONALES-Improcedencia \u00a0 para ordenar pago de retroactivo pensional, por no existir perjuicio \u00a0 irremediable ni afectaci\u00f3n del m\u00ednimo vital \u00a0 \u00a0<\/p>\n<p>La \u00a0 procedencia de la acci\u00f3n de tutela para obtener el pago de prestaciones sociales \u00a0 no puede desconocer que el ordenamiento jur\u00eddico prev\u00e9 procedimientos adecuados \u00a0 para el reconocimiento de las mismas. Es decir, por regla general las acreencias \u00a0 laborales, incluidas en aquellas los retroactivos pensionales a que un \u00a0 trabajador eventualmente pueda llegar a tener derecho, escapan a la procedencia \u00a0 del amparo en cuanto no exista certeza de la afectaci\u00f3n del m\u00ednimo vital y, \u00a0 adem\u00e1s, se demuestre que se han agotado los procedimientos ordinarios previstos \u00a0 por el ordenamiento jur\u00eddico con el fin de acreditar el derecho objeto de \u00a0 controversia. Este criterio ha sido reiterado por la Corporaci\u00f3n para precisar \u00a0 que la procedencia de la acci\u00f3n de tutela en estos casos exige: i) La existencia \u00a0 y titularidad del derecho reclamado; ii) Un grado importante de diligencia al \u00a0 momento de buscar la salvaguarda del derecho invocado; iii) Afectaci\u00f3n del \u00a0 m\u00ednimo vital como consecuencia de la negaci\u00f3n del derecho prestacional. En \u00a0 consecuencia si no se demuestra la concurrencia de los citados requisitos la \u00a0 acci\u00f3n de tutela deber\u00e1 declararse improcedente. \u00a0 \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0 \u00a0<\/p>\n<p>JORGE IV\u00c1N PALACIO PALACIO. \u00a0 \u00a0<\/p>\n<p>Bogot\u00e1, D.C., tres \u00a0 (3) de junio de dos mil quince (2015). \u00a0 \u00a0<\/p>\n<p>La Sala \u00a0 Sexta de Revisi\u00f3n de la Corte Constitucional, integrada por los Magistrados \u00a0 Jorge Iv\u00e1n Palacio Palacio, quien la preside, Jorge Ignacio Pretelt Chaljub y \u00a0 Alberto Rojas R\u00edos, en ejercicio de sus competencias constitucionales y legales, \u00a0 espec\u00edficamente las previstas en los art\u00edculos 86 y 241, numeral 9\u00ba de la \u00a0 Constituci\u00f3n Pol\u00edtica, y en los art\u00edculos 33 y concordantes del Decreto 2591 de \u00a0 1991, profiere la siguiente \u00a0 \u00a0<\/p>\n<p>SENTENCIA \u00a0 \u00a0<\/p>\n<p>Dentro \u00a0 del proceso de revisi\u00f3n de los fallos dictados por el Juzgado D\u00e9cimo \u00a0 Administrativo de Oralidad del Circuito de Cali, el pasado diecis\u00e9is (16) de \u00a0 octubre de 2014 y por el Tribunal Contencioso Administrativo del Valle del \u00a0 Cauca, el dieciocho (18) de noviembre del mismo a\u00f1o. \u00a0 \u00a0<\/p>\n<p>I.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0ANTECEDENTES \u00a0 \u00a0<\/p>\n<p>La \u00a0 se\u00f1ora Mar\u00eda Marly Santiba\u00f1ez Garc\u00eda, mediante apoderado judicial, interpuso \u00a0 acci\u00f3n de tutela contra COLPENSIONES, por cuanto considera que dicha \u00a0 administradora de pensiones vulner\u00f3 sus derechos fundamentales a la seguridad \u00a0 social, al m\u00ednimo vital y la vida digna, al negarle el pago de un retroactivo \u00a0 pensional dejado en suspenso en el acto administrativo que reconoci\u00f3 su derecho \u00a0 a la pensi\u00f3n de vejez, la cual deb\u00eda ser compartida entre la Gobernaci\u00f3n del \u00a0 Departamento del Valle del Cauca y el otrora Instituto del Seguro Social. \u00a0 \u00a0<\/p>\n<p>a.\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Hechos y pretensiones \u00a0 \u00a0<\/p>\n<p>De los documentos \u00a0 allegados al expediente se pueden extraer los siguientes: \u00a0 \u00a0<\/p>\n<p>1. La accionante labor\u00f3 como Auxiliar de Servicios Generales de la Secretar\u00eda de \u00a0 Salud del Departamento del Valle del Cauca, desde el 1\u00ba de diciembre de 1978, \u00a0 hasta el 15 de marzo del a\u00f1o 2000. \u00a0 \u00a0<\/p>\n<p>2. Fue pensionada por el ente territorial mediante Resoluci\u00f3n 3081 del 25 de \u00a0 noviembre de 2002, con efecto retroactivo al 16 de marzo de 2000, fecha en que \u00a0 se retir\u00f3 del servicio. \u00a0 \u00a0<\/p>\n<p>3. En la referida Resoluci\u00f3n se estipul\u00f3: \u201cEl Departamento del Valle del \u00a0 Cauca, cancelar\u00e1 la pensi\u00f3n de jubilaci\u00f3n y el retroactivo a partir del 16 de \u00a0 marzo de 2000, pero una vez el ISS reconozca la prestaci\u00f3n deber\u00e1 descontar el \u00a0 (sic) retroactivo liquidado todos los valores cancelados por concepto de mesadas \u00a0 y reintegrar dichas sumas al Departamento del Valle.\u201d \u00a0 \u00a0<\/p>\n<p>4. Se\u00f1al\u00f3 que mediante Resoluci\u00f3n N\u00fam. \u00a0 20979 del 14 de diciembre de 2009, el ISS le concedi\u00f3 la pensi\u00f3n de vejez, \u00a0 ordenando su inclusi\u00f3n en n\u00f3mina en el mes de enero de 2010; reconociendo en \u00a0 dicho acto administrativo un retroactivo pensional que asciende a la suma de \u00a0 treinta millones ochocientos cincuenta y siete mil quinientos cuarenta y seis \u00a0 pesos ($ 30.857.546). \u00a0 \u00a0<\/p>\n<p>5. Indic\u00f3 que el ISS orden\u00f3 en la \u00a0 mencionada resoluci\u00f3n dejar en suspenso el giro del retroactivo reconocido, \u00a0 hasta tanto se allegara autorizaci\u00f3n del empleador o del asegurado, para \u00a0 de esta manera tener certeza de qui\u00e9n es el beneficiario del mismo. Considera \u00a0 que dicho acto es ilegal a todas luces y que hasta la fecha no ha sido posible \u00a0 el pago de la mencionada cantidad. \u00a0 \u00a0<\/p>\n<p>6. Manifest\u00f3 que present\u00f3 una demanda \u00a0 ejecutiva con el fin de que le fuera otorgado el retroactivo, pero el Juzgado \u00a0 Tercero de Ejecuciones Laborales de Cali neg\u00f3 el mandamiento de pago y en \u00a0 consecuencia la demanda radicada con el N\u00famero 2013-756 fue retirada. \u00a0 \u00a0<\/p>\n<p>7. Adujo que en este momento padece de \u00a0 c\u00e1ncer, por tanto su estado de indefensi\u00f3n es notorio, as\u00ed como el perjuicio \u00a0 irremediable al que se ve sometida al no contar con el dinero retenido por el \u00a0 ISS-COLPENSIONES. \u00a0 \u00a0<\/p>\n<p>b. Solicitud de tutela \u00a0 \u00a0<\/p>\n<p>La accionante solicit\u00f3 al juez \u00a0 constitucional que al momento de resolver su asunto se ordene \u00a0al ISS, hoy \u00a0 COLPENSIONES, que en el menor tiempo posible proceda a pagar el retroactivo \u00a0 reconocido mediante la Resoluci\u00f3n N\u00fam. 20979 del 03 de marzo de 2011, el cual \u00a0 deber\u00e1 ser indexado. \u00a0 \u00a0<\/p>\n<p>c. Pruebas \u00a0 \u00a0<\/p>\n<p>a.\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Poder para actuar. \u00a0 \u00a0<\/p>\n<p>b.\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Copia de la c\u00e9dula de ciudadan\u00eda de la accionante. \u00a0 \u00a0<\/p>\n<p>c.\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Copia de la Resoluci\u00f3n N\u00fam. 20979 del 03 de marzo de 2011 y su respectiva \u00a0 notificaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>d.\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Copia de la historia cl\u00ednica de la accionante. \u00a0 \u00a0<\/p>\n<p>d. Respuesta de las \u00a0 entidades accionadas \u00a0 \u00a0<\/p>\n<p>El ISS-COLPENSIONES \u00a0 guard\u00f3 silencio en el proceso de tutela; la Gobernaci\u00f3n del Valle del Cauca, la \u00a0 cual fue vinculada de oficio, alleg\u00f3 de manera extempor\u00e1nea copia de la \u00a0 Resoluci\u00f3n N\u00fam. 3081del 25 de noviembre de 2002. \u00a0 \u00a0<\/p>\n<p>e. Decisiones \u00a0 objeto de revisi\u00f3n \u00a0 \u00a0<\/p>\n<p>Fallo de primera \u00a0 instancia \u00a0 \u00a0<\/p>\n<p>El Juzgado D\u00e9cimo \u00a0 Administrativo de Oralidad de Cali-Valle, neg\u00f3 el amparo tutelar por \u00a0 improcedente, al considerar que el pago de un retroactivo pensional no puede \u00a0 ordenarse por v\u00eda de tutela, toda vez que la accionante puede acudir a la \u00a0 justicia ordinaria laboral o la jurisdicci\u00f3n contencioso administrativa, donde \u00a0 se puede definir la controversia legal que existe entre las partes. \u00a0 \u00a0<\/p>\n<p>Impugnaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Argument\u00f3 que el \u00a0 juez de primera instancia solo se limit\u00f3 a referirse a la improcedencia de la \u00a0 tutela, desconociendo los derechos fundamentales invocados, dejando de lado la \u00a0 controversia central, la cual est\u00e1 centrada en el pago del retroactivo \u00a0 pensional, ello sin importar que hayan transcurrido cinco a\u00f1os desde el \u00a0 reconocimiento del mismo, por cuanto ahora es que ha surgido un perjuicio \u00a0 latente debido a la enfermedad que aqueja a la accionante. \u00a0 \u00a0<\/p>\n<p>Fallo de segunda \u00a0 instancia \u00a0 \u00a0<\/p>\n<p>El ad quem \u00a0 \u00a0confirm\u00f3 el fallo anterior al precisar que la tutela no es el mecanismo \u00a0 mediante el cual se pueda ordenar el pago de un retroactivo pensional, toda vez \u00a0 que el debate jur\u00eddico se centra en cuestiones de car\u00e1cter legal que trascienden \u00a0 el \u00e1mbito de la protecci\u00f3n inmediata de los derechos fundamentales que define la \u00a0 competencia del juez de tutela. \u00a0 \u00a0<\/p>\n<p>Consider\u00f3 que para \u00a0 este tipo de pretensiones existen otros medios ordinarios de defensa judicial, \u00a0 m\u00e1xime cuando no se acredit\u00f3 la presencia de un perjuicio irremediable que haga \u00a0 procedente la acci\u00f3n de amparo, por cuanto la accionante goza de la prestaci\u00f3n \u00a0 de los servicios de salud y en este momento percibe una pensi\u00f3n compartida entre \u00a0 COLPENSIONES y la Gobernaci\u00f3n del Valle del Cauca. \u00a0 \u00a0<\/p>\n<p>II. CONSIDERACIONES \u00a0 Y FUNDAMENTOS. \u00a0 \u00a0<\/p>\n<p>Competencia. \u00a0 \u00a0<\/p>\n<p>1.- Esta Corte es \u00a0 competente para revisar el presente fallo de tutela de conformidad con lo \u00a0 previsto en los art\u00edculos 86 y 241 de la Constituci\u00f3n, el Decreto 2591 de 1991 y \u00a0 las dem\u00e1s disposiciones pertinentes. \u00a0 \u00a0<\/p>\n<p>Planteamiento del caso y del problema jur\u00eddico. \u00a0 \u00a0<\/p>\n<p>2.- La \u00a0 se\u00f1ora Mar\u00eda Marly Santiba\u00f1ez Garc\u00eda solicit\u00f3 a COLPENSIONES el pago de un \u00a0 retroactivo reconocido en la Resoluci\u00f3n N\u00fam. 20979 del 3 de marzo de 2011, pero \u00a0 dejado en suspenso hasta que el empleador y el empleado pacten a qui\u00e9n \u00a0 corresponde esa suma de dinero. \u00a0 \u00a0<\/p>\n<p>3.- A su turno los \u00a0 jueces de tutela negaron el amparo al considerar que dicho asunto debe ser \u00a0 dirimido ante la jurisdicci\u00f3n laboral ordinaria o ante la contencioso \u00a0 administrativa, seg\u00fan el caso, sin tener en cuenta que la accionante es un \u00a0 sujeto de especial protecci\u00f3n constitucional debido a su avanzada edad y a la \u00a0 enfermedad que padece. \u00a0 \u00a0<\/p>\n<p>\u00be\u00a0\u00a0 \u00a0 Problema Jur\u00eddico \u00a0 \u00a0<\/p>\n<p>4.- Teniendo en \u00a0 cuenta el recuento que se acaba de hacer, se impone a la Corte dilucidar si la \u00a0 acci\u00f3n de tutela es el mecanismo id\u00f3neo para obtener\u00a0 el pago de los \u00a0 retroactivos pensionales liquidados por la entidad de seguridad social, \u00a0 prestaci\u00f3n que se encuentra en suspenso por efectos de la compartibilidad de la \u00a0 pensi\u00f3n con el empleador Gobernaci\u00f3n del Valle del Cauca.\u00a0 Para ello la \u00a0 Corte se referir\u00e1 (i) a la procedencia de la acci\u00f3n de tutela para el \u00a0 reconocimiento de derechos pensionales; ii) la instituci\u00f3n de la pensi\u00f3n \u00a0 compartida; iii) el retroactivo pensional en la jurisprudencia de esta Corte y; \u00a0 iv) se resolver\u00e1 el caso concreto. \u00a0 \u00a0<\/p>\n<p>5. \u00a0 Procedencia excepcional de la tutela para el reconocimiento de derechos \u00a0 pensionales. \u00a0 \u00a0<\/p>\n<p>La acci\u00f3n de tutela \u00a0 es un mecanismo que estableci\u00f3 la Constituci\u00f3n Pol\u00edtica de 1991, para proteger \u00a0 los derechos fundamentales de las personas, frente a lesiones o amenazas de \u00a0 vulneraci\u00f3n por parte de una autoridad p\u00fablica y, bajo ciertos supuestos, por \u00a0 parte de un particular. \u00a0 \u00a0<\/p>\n<p>Por tanto, se trata \u00a0 de un procedimiento judicial espec\u00edfico, aut\u00f3nomo, directo y sumario, que en \u00a0 ning\u00fan caso puede sustituir los procesos judiciales que establece la ley; en ese \u00a0 sentido la acci\u00f3n de tutela no procede cuando exista otro medio de defensa \u00a0 judicial, salvo que se configure un perjuicio irremediable, caso en el cual la tutela procede hasta que la autoridad \u00a0 correspondiente decida de fondo sobre el asunto. \u00a0 \u00a0<\/p>\n<p>De igual manera la \u00a0 Corte Constitucional[1] \u00a0en jurisprudencia reiterada ha se\u00f1alado que las controversias suscitadas con \u00a0 ocasi\u00f3n del reconocimiento de derechos pensionales no le corresponden a la \u00a0 jurisdicci\u00f3n constitucional en sede de tutela, dado que se trata de pretensiones \u00a0 de orden legal para cuya definici\u00f3n existen en el ordenamiento jur\u00eddico otras \u00a0 instancias, medios y procedimientos administrativos y judiciales ordinarios. \u00a0 \u00a0<\/p>\n<p>Ahora bien, para el caso espec\u00edfico del reconocimiento de retroactivos \u00a0 pensionales, esta Corporaci\u00f3n ha expresado de manera reiterada[2] la \u00a0 improcedencia de la tutela, ya que la misma no es el medio expedito para el \u00a0 cobro de dichas acreencias laborales en virtud de su car\u00e1cter subsidiario. De \u00a0 igual manera, ha sostenido que al pensionado estar percibiendo el pago de sus \u00a0 mesadas y por consiguiente la debida atenci\u00f3n en salud por parte del sistema de \u00a0 seguridad social, queda desvirtuado el perjuicio irremediable ante la no \u00a0 vulneraci\u00f3n del derecho al m\u00ednimo vital. \u00a0 \u00a0<\/p>\n<p>Al \u00a0 respecto, \u00a0 en la Sentencia T-056 de 2002 se precis\u00f3 lo siguiente: \u00a0 \u00a0<\/p>\n<p>\u201cEn cuanto al pago \u00a0 del valor del retroactivo pensional pretendido por el demandante, este no es \u00a0 viable solicitarlo por tutela, ya que esta Corporaci\u00f3n, ha reiterado en diversas \u00a0 oportunidades que el mecanismo de amparo no es el instrumento procesal adecuado \u00a0 para reclamar prestaciones sociales, salvo para tutelar el m\u00ednimo vital, es \u00a0 decir, que no es de la competencia del juez de tutela, el disponer el \u00a0 reconocimiento y la\u00a0 cancelaci\u00f3n de sumas de dinero por concepto de \u00a0 prestaciones sociales, mediante \u00f3rdenes judiciales, ya que, en el caso concreto, \u00a0 se trata de un derecho de car\u00e1cter legal en disputa el cual debe ser resuelto \u00a0 por la entidad de seguridad social teniendo en cuenta\u00a0 la normatividad que \u00a0 regula la materia.\u201d[3] \u00a0 \u00a0<\/p>\n<p>De igual manera en la Sentencia T-259 de 2004, esta \u00a0 Corporaci\u00f3n precis\u00f3: \u00a0 \u00a0<\/p>\n<p>\u00a0\u201cRespecto a \u00e9ste \u00a0 punto la Corte ha se\u00f1alado en m\u00faltiples oportunidades que la acci\u00f3n de tutela \u00a0 resulta improcedente para obtener la cancelaci\u00f3n del retroactivo que se \u00a0 encuentre insoluto[4], \u00a0 por cuanto la orden de pago respecto de acreencias de orden laboral, s\u00f3lo es \u00a0 procedente cuando se acredite que se encuentra en grave peligro el m\u00ednimo vital \u00a0 del accionante y no exista otro medio de defensa judicial id\u00f3neo.\u00a0 En el \u00a0 caso que nos ocupa, el hecho de que el actor se encuentre percibiendo el pago de \u00a0 las mesadas pensionales respectivas, releva a \u00e9sta Sala de impartir orden alguna \u00a0 en este sentido, toda vez que se evidencia que su m\u00ednimo vital no se encuentra \u00a0 actualmente afectado. Adem\u00e1s, debe precisarse que de aceptar la petici\u00f3n del \u00a0 actor, eventualmente se vulnerar\u00edan los derechos al debido proceso de los \u00a0 accionados, quienes no tendr\u00edan la oportunidad de controvertir los nuevos hechos \u00a0 planteados por el actor en el escrito se\u00f1alado. \u00a0 \u00a0<\/p>\n<p>Quiere decir lo \u00a0 anterior, que para la procedencia del reconocimiento del pago de retroactivos \u00a0 pensionales a trav\u00e9s de la acci\u00f3n de tutela, se debe demostrar que ha existido \u00a0 una vulneraci\u00f3n sistem\u00e1tica y repetitiva al m\u00ednimo vital del pensionado, tal \u00a0 como ocurre cuando el derecho a la pensi\u00f3n se ha causado con el pleno de los \u00a0 requisitos legales y la entidad encargada de reconocer el pago de la prestaci\u00f3n \u00a0 se demora meses o a\u00f1os en incluir al pensionado en n\u00f3mina, priv\u00e1ndole del \u00a0 sustento b\u00e1sico entre el momento de la causaci\u00f3n del derecho y el efectivo \u00a0 reconocimiento y pago del mismo. \u00a0 \u00a0<\/p>\n<p>No sucede lo mismo\u00a0 cuando la entidad de previsi\u00f3n social reconoce a tiempo \u00a0 la pensi\u00f3n o cuando un empleador se subroga en el pago de la misma sin que \u00a0 exista un lapso de interrupci\u00f3n en el pago de la prestaci\u00f3n, ello por cuanto \u00a0 est\u00e1 claro que en dicho evento no ha existido afectaci\u00f3n del m\u00ednimo vital, ya \u00a0 que el pensionado ha venido percibiendo peri\u00f3dicamente el pago de su mesada. \u00a0 \u00a0<\/p>\n<p>De tal manera que \u00a0 la procedencia de la acci\u00f3n de tutela para obtener el pago de prestaciones \u00a0 sociales no puede desconocer que el ordenamiento jur\u00eddico prev\u00e9 procedimientos \u00a0 adecuados para el reconocimiento de las mismas. Es decir, por regla general las \u00a0 acreencias laborales, incluidas en aquellas los retroactivos pensionales a que \u00a0 un trabajador eventualmente pueda llegar a tener derecho, escapan a la \u00a0 procedencia del amparo en cuanto no exista certeza de la afectaci\u00f3n del m\u00ednimo \u00a0 vital y, adem\u00e1s, se demuestre que se han agotado los procedimientos ordinarios \u00a0 previstos por el ordenamiento jur\u00eddico con el fin de acreditar el derecho objeto \u00a0 de controversia.\u00a0 \u00a0 \u00a0<\/p>\n<p>Este criterio ha sido reiterado por la Corporaci\u00f3n para precisar que la \u00a0 procedencia de la acci\u00f3n de tutela en estos casos exige[5]: i) La existencia y \u00a0 titularidad del derecho reclamado; ii) Un grado importante de diligencia al \u00a0 momento de buscar la salvaguarda del derecho invocado; iii) Afectaci\u00f3n del \u00a0 m\u00ednimo vital como consecuencia de la negaci\u00f3n del derecho prestacional. En \u00a0 consecuencia si no se demuestra la concurrencia de los citados requisitos la \u00a0 acci\u00f3n de tutela deber\u00e1 declararse improcedente. \u00a0 \u00a0<\/p>\n<p>6. La instituci\u00f3n jur\u00eddica de la pensi\u00f3n de \u00a0 jubilaci\u00f3n y la pensi\u00f3n compartida. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>En la sentencia C-1255 de 2001[6], \u00a0 la Corte Constitucional precis\u00f3 que antes de entrar en vigencia la Ley 100 de \u00a0 1993, que consagra el Sistema General de Pensiones, las expresiones de \u00a0 jubilaci\u00f3n y vejez se utilizaban para referirse a las pensiones adquiridas en \u00a0 virtud del cumplimiento de los requisitos previstos en la normas. Se otorgaban \u00a0 a: (i) los empleados oficiales, cuyo reconocimiento le correspond\u00eda a la Caja \u00a0 Nacional de Previsi\u00f3n \u2013CAJANAL o a otras cajas especiales de previsi\u00f3n; y \u00a0(ii) \u00a0 a los trabajadores privados, cuyos derechos fueran reconocidos directamente por \u00a0 las empresas empleadoras o por cajas especiales. \u00a0 \u00a0<\/p>\n<p>Para los empleados p\u00fablicos el \u00a0 art\u00edculo 1\u00b0 de la Ley 33 de 1985, establec\u00eda como requisito para obtener la \u00a0 pensi\u00f3n mensual vitalicia de jubilaci\u00f3n, que equival\u00eda al 75% del salario \u00a0 promedio devengado durante el \u00faltimo a\u00f1o de servicios, el cumplimiento de 20 \u00a0 a\u00f1os de servicios continuos o discontinuos y la edad de 55 a\u00f1os. La norma \u00a0 dispon\u00eda: \u00a0 \u00a0<\/p>\n<p>\u201cARTICULO 1o. El empleado oficial que sirva o haya servido veinte (20) a\u00f1os \u00a0 continuos o discontinuos y llegue a la edad de cincuenta y cinco a\u00f1os (55) \u00a0 tendr\u00e1 derecho a que por la respectiva Caja de Previsi\u00f3n se le pague una pensi\u00f3n \u00a0 mensual vitalicia de jubilaci\u00f3n equivalente al setenta y cinco por ciento (75%) \u00a0 del salario promedio que sirvi\u00f3 de base para los aportes durante el \u00faltimo a\u00f1o \u00a0 de servicio.\u201d \u00a0 \u00a0<\/p>\n<p>En el \u00a0 caso de los trabajadores privados, el art\u00edculo 260 del C\u00f3digo Sustantivo \u00a0 del Trabajo establec\u00eda una pensi\u00f3n mensual vitalicia de jubilaci\u00f3n equivalente \u00a0 al 75% del promedio de salarios devengados en el \u00faltimo a\u00f1o de servicio a cargo \u00a0 del empleador cuya empresa tuviera un capital mayor a $800.000, quien deb\u00eda \u00a0 reconocer y pagar a aquellos que llegaran a la edad de 50 a\u00f1os, si era mujer, o \u00a0 a los 55 a\u00f1os de edad, si era hombre y cumplieran 20 a\u00f1os de servicios continuos \u00a0 o discontinuos. La mencionada norma estipulaba: \u00a0 \u00a0<\/p>\n<p>\u201cARTICULO 260. DERECHO A LA PENSION. 1. Todo trabajador que preste servicios a \u00a0 una misma empresa de capital de ochocientos mil pesos ($ 800.000) o superior, \u00a0 que llegue o haya llegado a los cincuenta y cinco (55) a\u00f1os de edad, si es \u00a0 var\u00f3n, o a los cincuenta (50) a\u00f1os si es mujer, despu\u00e9s de veinte (20) a\u00f1os de \u00a0 servicios continuos o discontinuos, anteriores o posteriores a la vigencia de \u00a0 este C\u00f3digo, tiene derecho a una pensi\u00f3n mensual vitalicia de jubilaci\u00f3n o \u00a0 pensi\u00f3n de vejez, equivalente al setenta y cinco por ciento (75%) del promedio \u00a0 de los salarios devengados en el \u00faltimo a\u00f1o de servicio.\u201d (\u2026). \u00a0 \u00a0<\/p>\n<p>Por su parte, el Acuerdo 049 de 1990[7], \u00a0 aprobado por el Decreto 758 de 1990, estableci\u00f3 que el Instituto de Seguros \u00a0 Sociales reconocer\u00eda y pagar\u00eda una pensi\u00f3n de vejez a quienes llegaren a \u00a0 la edad de 55 a\u00f1os, en el caso de las mujeres, y de 60 a\u00f1os para los hombres, \u00a0 siempre que hubiesen cotizado 500 semanas en los \u00faltimos 20 a\u00f1os previos al \u00a0 cumplimiento de la edad o 1000 semanas en cualquier tiempo. El Acuerdo dispon\u00eda \u00a0 lo siguiente: \u00a0 \u00a0<\/p>\n<p>\u201cART\u00cdCULO 12. REQUISITOS DE LA PENSION POR VEJEZ. Tendr\u00e1n derecho a la pensi\u00f3n de vejez las personas que re\u00fanan los \u00a0 siguientes requisitos: \/\/ a) Sesenta (60) o m\u00e1s a\u00f1os de edad si se es var\u00f3n o \u00a0 cincuenta y cinco (55) o m\u00e1s a\u00f1os de edad, si se es mujer y, \/\/ b) Un m\u00ednimo de \u00a0 quinientas (500) semanas de cotizaci\u00f3n pagadas durante los \u00faltimos veinte (20) \u00a0 a\u00f1os anteriores al cumplimiento de las edades m\u00ednimas, o haber acreditado un \u00a0 n\u00famero de un mil (1.000) semanas de cotizaci\u00f3n, sufragadas en cualquier tiempo.\u201d \u00a0 \u00a0<\/p>\n<p>La anterior disposici\u00f3n, tambi\u00e9n estipul\u00f3 \u00a0 la \u201ccompartibilidad\u201d de las pensiones entre el empleador y el Instituto \u00a0 de Seguros Sociales para las pensiones que el empresario reconociera a sus \u00a0 trabajadores, bien fuera de car\u00e1cter legal (art\u00edculo 16), por sanci\u00f3n ante el \u00a0 despido injusto (art\u00edculo 17) o para las extralegales por convenci\u00f3n colectiva, \u00a0 pacto colectivo, laudo arbitral o voluntariamente (art\u00edculo 18). El empleador \u00a0 deb\u00eda seguir realizando los aportes a la seguridad social en pensiones al ISS, \u00a0 hasta que el trabajador cumpliera con los requisitos de ley para el \u00a0 reconocimiento de la pensi\u00f3n de vejez a la que tuviere derecho. El \u00a0 reconocimiento que hac\u00eda el ISS por pensi\u00f3n de vejez liberaba al empleador de \u00a0 pagar la prestaci\u00f3n de jubilaci\u00f3n, pero si el valor de la pensi\u00f3n que otorgara \u00a0 dicho instituto resultaba inferior al valor que el empleador reconoci\u00f3 como \u00a0 pensi\u00f3n extralegal o legal, estar\u00eda a cargo de \u00e9ste \u00faltimo el mayor valor que \u00a0 reconoci\u00f3. Trat\u00e1ndose de compartibilidad de pensiones legales de que trata el \u00a0 caso que ocupa la atenci\u00f3n de esta Sala de Revisi\u00f3n, el art\u00edculo 16 del Acuerdo \u00a0 049 de 1990 dispon\u00eda: \u00a0 \u00a0<\/p>\n<p>\u201cART\u00cdCULO 16. COMPARTIBILIDAD DE LAS PENSIONES LEGALES DE JUBILACION.\u00a0Los trabajadores \u00a0 que al iniciarse la obligaci\u00f3n de asegurarse en el Instituto de Seguros Sociales \u00a0 contra los riesgos de invalidez, vejez y muerte, lleven 10 a\u00f1os o m\u00e1s de \u00a0 servicios continuos o discontinuos en una misma empresa de capital de \u00a0 ochocientos mil pesos ($ 800.000.00) moneda corriente o superior, ingresar\u00e1n al \u00a0 seguro obligatorio como afiliados para el riesgo de invalidez, vejez y muerte. \u00a0 Al cumplirse el tiempo de servicios y la edad exigidos por la ley para las \u00a0 pensiones plenas o especiales en ella consagradas, podr\u00e1n exigir la jubilaci\u00f3n a \u00a0 cargo del patrono y \u00e9ste estar\u00e1 obligado a pagar dicha pensi\u00f3n de jubilaci\u00f3n, \u00a0 pero el patrono continuar\u00e1 cotizando en este seguro hasta cuando el trabajador \u00a0 cumpla con los requisitos m\u00ednimos exigidos por el Instituto para otorgar la \u00a0 pensi\u00f3n de vejez, y en este momento, el Instituto proceder\u00e1 a cubrir dicha \u00a0 pensi\u00f3n, siendo de cuenta del patrono \u00fanicamente el mayor valor, si lo hubiere, \u00a0 entre la pensi\u00f3n otorgada por el Instituto y la que ven\u00eda cubriendo al \u00a0 pensionado.\u201d \u00a0 \u00a0<\/p>\n<p>De lo anterior puede concluir esta \u00a0 Corporaci\u00f3n que antes de entrar en vigencia la Ley 100 de 1993 en materia de \u00a0 pensiones, la expresi\u00f3n pensi\u00f3n de jubilaci\u00f3n ten\u00eda \u00a0 relaci\u00f3n con las prestaciones reconocidas a: (i) los empleados p\u00fablicos, cuyos \u00a0 derechos pensionales eran reconocidos y pagados por CAJANAL, por cajas \u00a0 especiales; o a (ii) los trabajadores privados cuyas pensiones eran reconocidas \u00a0 y pagadas por sus empleadores, siempre que cumplieran con los requisitos \u00a0 exigidos que hac\u00edan referencia espec\u00edficamente al \u201ctiempo de servicio\u201d; \u00a0 mientras que la expresi\u00f3n pensi\u00f3n de vejez era un t\u00e9rmino \u00a0 relacionado con las prestaciones reconocidas por el Instituto de Seguros \u00a0 Sociales a los trabajadores privados afiliados a \u00e9l y cuyos requisitos hac\u00edan \u00a0 referencia a \u201csemanas cotizadas\u201d, que era el sistema de c\u00f3mputo previsto \u00a0 en las normas. En los casos de reconocimiento de las pensiones de jubilaci\u00f3n \u00a0 legales, extralegales o las originadas en el despido injusto, el ordenamiento \u00a0 legal preve\u00eda el sistema de la compartibilidad de pensiones entre los patronos y \u00a0 el ISS, una vez se cumplieran los requisitos exigidos para obtener la pensi\u00f3n de \u00a0 vejez, con lo cual se liberaba al empleador del cumplimiento de esta obligaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Con la entrada del Sistema General de \u00a0 Pensiones previsto en la Ley 100 de 1993, fueron derogados los anteriores \u00a0 ordenamientos legales, quedando vigentes solamente para quienes fueran \u00a0 beneficiarios del R\u00e9gimen de Transici\u00f3n previsto en el art\u00edculo 36 de la misma \u00a0 ley. De esta forma el sistema de pensiones se unific\u00f3 para los trabajadores \u00a0 p\u00fablicos y privados, y a partir de su entrada en vigor la contingencia de la \u00a0 vejez ser\u00eda cubierta por una prestaci\u00f3n que en todos los casos se denomina \u00a0 pensi\u00f3n de vejez, sin considerar si se trata de empleados p\u00fablicos o de \u00a0 trabajadores privados, desapareciendo con ello del ordenamiento jur\u00eddico \u00a0 colombiano en materia de pensiones la expresi\u00f3n pensi\u00f3n de jubilaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>7. Del \u00a0 retroactivo pensional. \u00a0 \u00a0<\/p>\n<p>En lo que concierne \u00a0 al retroactivo pensional esta Corporaci\u00f3n \u00a0ha manifestado que en algunos casos \u00a0 espec\u00edficos s\u00ed se puede reconocer el pago del mismo a trav\u00e9s de la tutela, una \u00a0 vez verificada la afectaci\u00f3n del m\u00ednimo vital y el consecuente sometimiento del \u00a0 accionante a un perjuicio irremediable, de lo contario, como se precis\u00f3 en el \u00a0 ac\u00e1pite de la procedencia, no es viable exigir el reconocimiento de esta \u00a0 prestaci\u00f3n a trav\u00e9s de la acci\u00f3n de amparo. \u00a0 \u00a0<\/p>\n<p>Uno de los casos en \u00a0 que la Corte concedi\u00f3 el pago del retroactivo pensional, atendiendo a las \u00a0 circunstancias propias del accionante est\u00e1 referenciado en la sentencia T-722 de \u00a0 2012, donde se resolvi\u00f3 el derecho pensional de una tutelante que pese a haber \u00a0 cumplido con los requisitos para la pensi\u00f3n de vejez, el ISS mediante una cadena \u00a0 sistem\u00e1tica de errores desconoci\u00f3 los tiempos de cotizaci\u00f3n certificados en \u00a0 Resoluciones anteriores, demor\u00e1ndose m\u00e1s de cuatro a\u00f1os en resolver de fondo el \u00a0 asunto de la peticionaria. \u00a0 \u00a0<\/p>\n<p>En este puntual \u00a0 caso, al haber quedado demostrado que la petente hab\u00eda causado el derecho a la \u00a0 pensi\u00f3n de vejez, que el no reconocimiento de la misma por parte del ISS afect\u00f3 \u00a0 gravemente su m\u00ednimo vital y el acceso a los servicios de salud, la Corte \u00a0 consider\u00f3 prudente reconocer el derecho prestacional junto con el retroactivo. \u00a0 Al respecto se\u00f1al\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cPara esta Corte la actuaci\u00f3n por parte del ISS, que desconoci\u00f3 el derecho a una \u00a0 pensi\u00f3n de vejez a la ciudadana Guillermina T\u00e9llez de V\u00e1squez no solo impidi\u00f3 el \u00a0 acceso oportuno a su mesada pensional, sino que puso en peligro la vida e \u00a0 integridad de la accionante, puesto que tal como lo refiri\u00f3 en la demanda no \u00a0 percibe otra fuente de ingresos de manera regular.\u201d \u00a0 \u00a0<\/p>\n<p>En lo que respecta \u00a0 a la pretensi\u00f3n de conceder el pago retroactivo de la pensi\u00f3n de vejez, indic\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cEn primer lugar, cuando el conflicto puesto a consideraci\u00f3n del juez \u00a0 constitucional versa en torno al\u00a0reconocimiento de un derecho pensional, \u00e9ste \u00a0 adquiere competencia para pronunciarse y amparar la pretensi\u00f3n de pago \u00a0 retroactivo de este derecho, cuando, a juicio de la Sala: a) hay certeza en la \u00a0 configuraci\u00f3n del derecho pensional y b) se hace evidente la afectaci\u00f3n al \u00a0 m\u00ednimo vital, al constatarse que la pensi\u00f3n es la \u00fanica forma de garantizar la \u00a0 subsistencia de la accionante y que por una conducta antijur\u00eddica de la entidad \u00a0 demandada, los medios econ\u00f3micos para vivir han estado ausentes desde el momento \u00a0 en que se caus\u00f3 el derecho hasta la fecha de concesi\u00f3n definitiva del amparo. \u00a0 Estas dos circunstancias hacen que el conflicto que por naturaleza es legal y \u00a0 que posee medios ordinarios para su defensa, mute en uno de \u00edndole \u00a0 constitucional, en donde los medios ordinarios se tornan ineficaces para el \u00a0 amparo de los derechos vulnerados o amenazados.\u201d[8] \u00a0 \u00a0<\/p>\n<p>Lo anterior por \u00a0 cuanto se logr\u00f3 demostrar la certeza de la existencia del derecho prestacional, \u00a0 as\u00ed como la afectaci\u00f3n al m\u00ednimo vital de la accionante, debido a una carga que \u00a0 no debi\u00f3 soportar por las irregularidades en la actuaci\u00f3n desplegada por el ISS. \u00a0 \u00a0<\/p>\n<p>En casos contrarios, donde no ha existido interrupci\u00f3n en el reconocimiento de \u00a0 la mesada pensional, esta Corte ha se\u00f1alado que la acci\u00f3n de tutela no puede \u00a0 entrar a dirimir conflictos de rango legal desplazando los medios ordinarios \u00a0que el legislador creo para su reconocimiento. Lo anterior se ha argumentado \u00a0 en las \u00a0sentencias T-1419 de 2000, T-056 de 2002, T-765 de 2002, T-628 de \u00a0 2004, \u00a0 T-1132 de 2005 y, recientemente en la T-628 de 2013, al se\u00f1alar: \u00a0 \u00a0<\/p>\n<p>\u201cEn cuanto al pago \u00a0 del valor del retroactivo pensional pretendido por el demandante, este no es \u00a0 viable solicitarlo por tutela, ya que esta Corporaci\u00f3n, ha reiterado en diversas \u00a0 oportunidades que el mecanismo de amparo no es el instrumento procesal adecuado \u00a0 para reclamar prestaciones sociales, salvo para tutelar el m\u00ednimo vital, es \u00a0 decir, que no es de la competencia del juez de tutela, el disponer el \u00a0 reconocimiento y la cancelaci\u00f3n de sumas de dinero por concepto de prestaciones \u00a0 sociales, mediante \u00f3rdenes judiciales, ya que, en el caso concreto, se trata de \u00a0 un derecho de car\u00e1cter legal en disputa el cual debe ser resuelto por la entidad \u00a0 de seguridad social teniendo en cuenta\u00a0 la normatividad que regula la \u00a0 materia\u201d. \u00a0 \u00a0<\/p>\n<p>Se tiene entonces \u00a0 que la acci\u00f3n de tutela no es la v\u00eda principal para lograr el reconocimiento de \u00a0 acreencias prestacionales (pago del retroactivo), porque la competencia para \u00a0 dirimir esta clase de conflictos, en principio, la ostenta la jurisdicci\u00f3n \u00a0 ordinaria o\u00a0 la contencioso administrativa, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>As\u00ed las \u00a0 cosas, \u00a0 exclusivamente ante la falta de un medio id\u00f3neo o si la ineficacia del \u00a0 disponible, amenaza derechos fundamentales en tal medida que puede concluir en \u00a0 la generaci\u00f3n de un perjuicio irremediable, la tutela es procedente siempre y \u00a0 cuando adem\u00e1s de la afectaci\u00f3n de su m\u00ednimo vital se cumplan los siguientes \u00a0 requisitos: i) que el interesado tenga la calidad de pensionado o jubilado, \u00a0 ii) que las condiciones materiales que le rodean exijan su protecci\u00f3n especial, \u00a0 iii) que se haya agotado la v\u00eda gubernativa y iv) que se haya iniciado proceso \u00a0 ordinario o contencioso administrativo; adicionalmente, para determinar la \u00a0 probable ineficacia del medio ordinario de defensa el juez de tutela deber\u00e1 \u00a0 tener en cuenta los siguientes aspectos, que la Sala reitera: \u00a0 \u00a0<\/p>\n<p>\u201c(i) la edad para ser considerado sujeto de \u00a0 especial de protecci\u00f3n; (ii) la condici\u00f3n f\u00edsica, econ\u00f3mica o mental; (iii) el \u00a0 grado de afectaci\u00f3n de los derechos fundamentales, en particular del derecho al \u00a0 m\u00ednimo vital; (iv) la existencia previa del derecho y la acreditaci\u00f3n por parte \u00a0 del interesado de la presunta afectaci\u00f3n; y (v) el despliegue de cierta \u00a0 actividad administrativa y procesal tendiente a obtener la protecci\u00f3n de sus \u00a0 derechos\u201d[9]. \u00a0 \u00a0<\/p>\n<p>En \u00a0 conclusi\u00f3n, esta Corte ha reconocido por v\u00eda de tutela el pago del retroactivo \u00a0 pensional cuando el accionante logra demostrar: i) la certeza de que le asiste \u00a0 el derecho al retroactivo pensional; ii) la afectaci\u00f3n directa del derecho al \u00a0 m\u00ednimo vital ante el no reconocimiento del mismo; iii) que ha adelantado los \u00a0 recursos en la v\u00eda gubernativa con el fin de controvertir los actos que \u00a0 desconocen su derecho y; iv) que ha iniciado el proceso ordinario o contencioso \u00a0 administrativo pertinente, en busca del amparo de sus derechos. \u00a0 \u00a0<\/p>\n<p>7. El caso concreto \u00a0 \u00a0<\/p>\n<p>La Sala verificar\u00e1 si en el presente asunto se cumple con los requisitos \u00a0 exigidos por la jurisprudencia para la procedencia de la acci\u00f3n de tutela\u00a0 \u00a0 en materia del pago de los retroactivos pensionales, atendiendo especialmente a \u00a0 la condici\u00f3n en que se encuentra la demandante, por ser un sujeto de especial \u00a0 protecci\u00f3n constitucional al tratarse de una persona de la tercera edad y la \u00a0 cual padece una grave enfermedad. \u00a0 \u00a0<\/p>\n<p>Cabe precisar que el Instituto de Seguros Sociales reconoci\u00f3 por medio de un \u00a0 acto administrativo el retroactivo de la accionante dej\u00e1ndolo en suspenso hasta \u00a0 tanto se resuelva la controversia acerca de la compartibilidad de la pensi\u00f3n \u00a0 entre el empleador jubilante (Gobernaci\u00f3n del Valle del Cauca) y la pensionada \u00a0 (Mar\u00eda Marly Santiba\u00f1ez Garc\u00eda). \u00a0 \u00a0<\/p>\n<p>Se debe enunciar de entrada que seg\u00fan los criterios fijados por esta \u00a0 Corporaci\u00f3n, respecto a utilizar la acci\u00f3n de tutela para obtener el pago de \u00a0 retroactivos, el apoderado de la demandante no demuestra los aspectos \u00a0 fundamentales para su procedencia, esto es: i) la certeza de que el retroactivo \u00a0 pensional corresponde a la accionante; ii) la afectaci\u00f3n al m\u00ednimo vital; iii) \u00a0 el agotamiento de los recursos de la v\u00eda gubernativa y; iv) el haber acudido \u00a0 ante la jurisdicci\u00f3n ordinaria a instaurar el proceso laboral pertinente. \u00a0 \u00a0<\/p>\n<p>Lo primero por cuanto no existe certeza sobre qui\u00e9n debe ser el beneficiario del \u00a0 retroactivo reconocido por el ISS, toda vez que la Gobernaci\u00f3n del Valle del \u00a0 Cauca en la Resoluci\u00f3n N\u00fam. 3081 de 2002, indic\u00f3 lo siguiente: \u201cEl Departamento \u00a0 del Valle del Cauca, cancelar\u00e1 la pensi\u00f3n de jubilaci\u00f3n y el retroactivo a \u00a0 partir del 16 de marzo de 2000, pero una vez el ISS reconozca la prestaci\u00f3n \u00a0 deber\u00e1 descontar el (sic) retroactivo liquidado todos los valores cancelados por \u00a0 concepto de mesadas y reintegrar dichas sumas al Departamento del Valle.\u201d \u00a0 \u00a0<\/p>\n<p>Quiere decir lo anterior que el empleador dej\u00f3 constancia en el acto \u00a0 administrativo que reconoci\u00f3 la pensi\u00f3n de la accionante de su intenci\u00f3n de \u00a0 reclamar para s\u00ed el retroactivo que surgiera al momento de que el ISS lo \u00a0 subrogara en el pago de la prestaci\u00f3n. Ello tiene sentido en la medida en que el \u00a0 empleador reconoci\u00f3 y pag\u00f3 una pensi\u00f3n de jubilaci\u00f3n a la se\u00f1ora Santiba\u00f1ez \u00a0 Garc\u00eda y adem\u00e1s continu\u00f3 cotizando a la entidad de previsi\u00f3n social hasta que la \u00a0 accionante cumpliera los requisitos para cobrar la pensi\u00f3n entre ellos \u00a0 compartida. \u00a0 \u00a0<\/p>\n<p>Lo anterior aunado a que la Gobernaci\u00f3n del Valle del Cauca ven\u00eda ya \u00a0 reconociendo la pensi\u00f3n de jubilaci\u00f3n a la se\u00f1ora Santiba\u00f1ez Garc\u00eda desde el 16 \u00a0 de marzo de 2000, sin que se hubiera demostrado que su empleador hubiese dejado \u00a0 de pagar la mesada pensional correspondiente entre el momento en que le fue \u00a0 reconocida por la Gobernaci\u00f3n del Valle y aquel en que fue subrogada por el ISS. \u00a0 \u00a0<\/p>\n<p>En esa medida, al no existir interrupci\u00f3n entre el momento en que se caus\u00f3 el \u00a0 derecho pensional y el disfrute del mismo, no se puede decir que ha surgido en \u00a0 favor de la accionante un derecho cierto al retroactivo pensional. \u00a0 \u00a0<\/p>\n<p>Otra cosa es la discusi\u00f3n existente entre la accionante y el empleador que la \u00a0 pension\u00f3 (Gobernaci\u00f3n del Valle), de si por haberse presentado en el a\u00f1o 2010 a \u00a0 reclamar la pensi\u00f3n compartida ante el ISS, habiendo causado ese derecho mucho \u00a0 tiempo antes, el retroactivo pertinente deb\u00eda corresponderle a la accionante o \u00a0 al ente territorial. \u00a0 \u00a0<\/p>\n<p>Para dirimir dicho asunto se hace necesario entrar en un debate probatorio \u00a0 \u00a0profundo donde se determine si existi\u00f3 alguna manifestaci\u00f3n expresa por parte \u00a0 del empleador o del trabajador donde se manifestara a qui\u00e9n le pertenecer\u00eda el \u00a0 eventual retroactivo. De igual manera, se debe dilucidar si la Gobernaci\u00f3n del \u00a0 Valle debe pagar un mayor valor por la diferencia entre la pensi\u00f3n reconocida \u00a0 por esta y la que posteriormente reconoci\u00f3 el ISS. Todo ello lleva a concluir \u00a0 que este tipo de debate se debi\u00f3 surtir en la jurisdicci\u00f3n ordinaria, donde se \u00a0 pod\u00edan controvertir ampliamente los argumentos de las partes, se hubiera podido \u00a0 aportar las pruebas \u00a0pertinentes y as\u00ed el juez de la causa entrara a decidir a \u00a0 qui\u00e9n realmente le corresponder\u00eda el derecho al retroactivo. \u00a0 \u00a0<\/p>\n<p>Lo segundo, toda vez que la pensi\u00f3n de jubilaci\u00f3n de la accionante ha sido \u00a0 pagada mes a mes, sin interrupci\u00f3n, en un primer momento por la Gobernaci\u00f3n del \u00a0 Valle del Cauca (a\u00f1os 2000-2010), despu\u00e9s por el Instituto del Seguro Social \u00a0 (a\u00f1os 2010 hasta la fecha). En esta medida, la sola afirmaci\u00f3n de que la se\u00f1ora \u00a0 padece una enfermedad catastr\u00f3fica no permite inferir la afectaci\u00f3n de su m\u00ednimo \u00a0 vital. \u00a0 \u00a0<\/p>\n<p>De otro lado, el ISS reconoci\u00f3 en la Resoluci\u00f3n 20979 del 3 de marzo de 2011 la \u00a0 pensi\u00f3n de vejez con la respectiva fecha de inclusi\u00f3n en n\u00f3mina y el monto a \u00a0 pagar, con lo cual garantiz\u00f3 el m\u00ednimo vital de la accionante, que de ninguna \u00a0 manera se muestra amenazado por falta de pago del retroactivo. \u00a0 \u00a0<\/p>\n<p>Por tanto, no basta con aludir que solo hasta ahora la accionante se encuentra \u00a0 inmersa en un perjuicio irremediable por la enfermedad que padece, toda vez que \u00a0 debi\u00f3 interponer prontamente los recursos en la v\u00eda gubernativa contra la \u00a0 Resoluci\u00f3n que dej\u00f3 en suspenso el pago del retroactivo pensional en el a\u00f1o \u00a0 2010, para luego acudir ante la jurisdicci\u00f3n laboral ordinaria en caso de que el \u00a0 ISS persistiera en su negativa. Con dicha omisi\u00f3n se desconoci\u00f3 el tercero de \u00a0 los requisitos de procedibilidad de la presente tutela, cual era agotar los \u00a0 recursos de ley. \u00a0 \u00a0<\/p>\n<p>As\u00ed mismo, tampoco se cumpli\u00f3 con el cuarto de los requisitos que la \u00a0 jurisprudencia exige para la procedencia de la tutela en el caso del pago de \u00a0 retroactivos pensionales, cual es haber acudido a la jurisdicci\u00f3n ordinaria. En \u00a0 el presente asunto, el apoderado de la accionante solo manifiesta que en el a\u00f1o \u00a0 2013 inici\u00f3 una demanda ejecutiva laboral que correspondi\u00f3 por reparto al \u00a0 Juzgado Tercero de Ejecuciones Laborales de Cali, quien deneg\u00f3 el mandamiento de \u00a0 pago ante la falta de claridad en el derecho. En ese momento debi\u00f3 el apoderado \u00a0 judicial corregir su actuaci\u00f3n e iniciar el correspondiente proceso para que se \u00a0 declarara en juicio a quien se deb\u00eda entregar el dinero producto del \u00a0 retroactivo. \u00a0 \u00a0<\/p>\n<p>En estas \u00a0 condiciones, la discusi\u00f3n sobre a qui\u00e9n el ISS debe pagar la suma que qued\u00f3 en \u00a0 suspenso de ser entregada es de \u00edndole legal, lo que escapa a la competencia del \u00a0 juez de tutela, m\u00e1xime cuando, como se dijo, no est\u00e1 demostrada la vulneraci\u00f3n \u00a0 de ning\u00fan derecho fundamental, bajo el entendido que la accionante como \u00a0 pensionada est\u00e1 recibiendo la mesada y la debida atenci\u00f3n en salud por parte del \u00a0 sistema general de la seguridad social. \u00a0 \u00a0<\/p>\n<p>De otra parte, en los actos administrativos (resoluciones), tanto la Gobernaci\u00f3n \u00a0 del Valle, como el Instituto de Seguros Sociales, advirtieron acerca de la \u00a0 naturaleza compartible de la pensi\u00f3n, raz\u00f3n objetiva que indubitablemente debe \u00a0 ser resuelta por el juez de la jurisdicci\u00f3n ordinaria, sin que la acci\u00f3n de \u00a0 tutela sea el instrumento id\u00f3neo para reclamar estas acreencias laborales y \u00a0 soslayar la v\u00eda judicial ordinaria para resolver la controversia. \u00a0 \u00a0<\/p>\n<p>Por lo expuesto, se confirmar\u00e1 el fallo \u00a0 proferido por el Tribunal Contencioso Administrativo del Valle del Cauca el \u00a0 pasado dieciocho (18) de noviembre de 2014, en el cual se declar\u00f3 la \u00a0 improcedencia de la acci\u00f3n de tutela. \u00a0 \u00a0<\/p>\n<p>V. DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Sexta de Revisi\u00f3n de la Corte Constitucional, \u00a0 administrando justicia en nombre del pueblo y por mandato de la Constituci\u00f3n, \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>RESUELVE \u00a0 \u00a0<\/p>\n<p>PRIMERO.- CONFIRMAR\u00a0la sentencia \u00a0 proferida el dieciocho (18) de noviembre de dos mil catorce (2014) por el \u00a0 Tribunal Contencioso Administrativo del Valle del Cauca, el cual declar\u00f3 la \u00a0 improcedencia de la acci\u00f3n de tutela en el presente asunto. \u00a0 \u00a0<\/p>\n<p>SEGUNDO.- REQUERIR a la Gobernaci\u00f3n \u00a0 del Valle del Cauca para que en un t\u00e9rmino de quince d\u00edas despu\u00e9s de la \u00a0 notificaci\u00f3n de esta providencia, allegue los documentos necesarios ante \u00a0 COLPENSIONES, para que se surta el tr\u00e1mite correspondiente a fin de definir \u00a0 sobre el beneficiario del retroactivo. \u00a0 \u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese, c\u00famplase e ins\u00e9rtese en la Gaceta de la Corte \u00a0 Constitucional. \u00a0 \u00a0<\/p>\n<p>JORGE IV\u00c1N PALACIO PALACIO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>JORGE IGNACIO PRETELT CHALJUB \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>ALBERTO ROJAS R\u00cdOS \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0 \u00a0<\/p>\n<p>Secretaria General \u00a0 \u00a0<\/p>\n<p>[1] Ver, entre otras, \u00a0 las Sentencias\u00a0 T-290, T-657 y T-1229 de 2004, T-734 y T-1235 de 2004 y \u00a0 T-716 de 2004. \u00a0 \u00a0<\/p>\n<p>[2] \u00a0Ver, entre otras, las Sentencias\u00a0 T-628 de 2004, T-259 de 2004. \u00a0 \u00a0<\/p>\n<p>[3] \u00a0Corte Constitucional, Sentencia T-1419 de 2000. \u00a0 \u00a0<\/p>\n<p>[4] \u00a0 Corte Constitucional, Sentencia T-1419 de 2000. \u00a0 \u00a0<\/p>\n<p>[5] Sentencia T-019 de 2012. \u00a0 \u00a0<\/p>\n<p>[6] \u00a0reiterada en la sentencia T-1233 de 2008. \u00a0 \u00a0<\/p>\n<p>[7] \u00a0El acuerdo 049 de 1990, derog\u00f3 en su integridad el acuerdo 029 de 1985, aprobado \u00a0 por el Decreto 2879 de 1985. \u00a0 \u00a0<\/p>\n<p>[8] Sentencia T \u2013 482 de 2010. \u00a0 \u00a0<\/p>\n<p>[9] La sentencia T-083\/04 \u00a0 desarrolla los factores para la procedencia transitoria de la acci\u00f3n de tutela, \u00a0 los cuales inicialmente fueron enunciados en la sentencia SU-975\/03, reiterada \u00a0 en sentencia T-104-06.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-341-15 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 Sentencia T-341\/15 \u00a0 \u00a0 PENSION DE JUBILACION Y PENSION COMPARTIDA-Naturaleza jur\u00eddica \u00a0 \u00a0 COMPARTIBILIDAD PENSIONAL-Finalidad \u00a0 \u00a0 ACCION DE TUTELA PARA EL RECONOCIMIENTO DE ACREENCIAS PENSIONALES-Improcedencia \u00a0 para ordenar pago de retroactivo pensional, por no existir perjuicio \u00a0 irremediable ni afectaci\u00f3n del m\u00ednimo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[103],"tags":[],"class_list":["post-22653","post","type-post","status-publish","format-standard","hentry","category-tutelas-2015"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/22653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=22653"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/22653\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=22653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=22653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=22653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}