{"id":25307,"date":"2024-06-28T18:32:43","date_gmt":"2024-06-28T18:32:43","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/06\/28\/t-119-17\/"},"modified":"2024-06-28T18:32:43","modified_gmt":"2024-06-28T18:32:43","slug":"t-119-17","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-119-17\/","title":{"rendered":"T-119-17"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia T-119\/17 \u00a0<\/p>\n<p>LEY ESTATUTARIA DEL DERECHO DE PETICION-Regulaci\u00f3n de la informaci\u00f3n sometida a reserva\u00a0 \u00a0<\/p>\n<p>Es cierto que antes del 2015 la jurisprudencia constitucional hab\u00eda sostenido que la acci\u00f3n de tutela era el mecanismo judicial id\u00f3neo para solicitar la protecci\u00f3n del derecho fundamental de petici\u00f3n, ante la inexistencia de otro procedimiento ordinario. Sin embargo, hoy en d\u00eda, es claro que con la expedici\u00f3n de la mencionada Ley Estatutaria los ciudadanos cuentan con un proceso destinado exclusivamente a que un funcionario judicial decida, de manera imparcial, si los documentos que una determinada autoridad p\u00fablica ha clasificado como \u201creservados\u201d deben o no ser entregados al solicitante, con lo cual la acci\u00f3n de amparo recobra su car\u00e1cter subsidiario para efectos de proteger el derecho fundamental antedicho.\u00a0 \u00a0<\/p>\n<p>DERECHO FUNDAMENTAL AL DEBIDO PROCESO ADMINISTRATIVO-Alcance y contenido\u00a0 \u00a0<\/p>\n<p>DERECHO FUNDAMENTAL AL DEBIDO PROCESO ADMINISTRATIVO-Vulneraci\u00f3n por negativa de autoridades universitarias de entregar documentos, bajo el argumento de que estos estaban cubiertos por la reserva del sumario \u00a0<\/p>\n<p>DERECHO FUNDAMENTAL AL DEBIDO PROCESO ADMINISTRATIVO-Orden a Universidad adoptar un protocolo de gesti\u00f3n de peticiones \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Referencia: Expediente T- 5.775.991\u00a0 \u00a0<\/p>\n<p>Acci\u00f3n de tutela interpuesta por Irma Casta\u00f1eda Ram\u00edrez contra la Universidad Distrital Francisco Jos\u00e9 de Caldas.\u00a0 \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>LUIS ERNESTO VARGAS SILVA \u00a0<\/p>\n<p>Bogot\u00e1, D.C., veintisiete (27) de febrero de dos mil diecisiete (2017) \u00a0<\/p>\n<p>La Sala Novena de Revisi\u00f3n de la Corte Constitucional, en ejercicio de sus competencias constitucionales y legales, espec\u00edficamente las previstas en los art\u00edculos 86 y 241 numeral 9 de la Constituci\u00f3n Pol\u00edtica y en el Decreto Ley 2591 de 1991, profiere la siguiente \u00a0<\/p>\n<p>SENTENCIA \u00a0<\/p>\n<p>En el tr\u00e1mite de revisi\u00f3n de los fallos proferidos por el Juzgado Veinticinco Penal Municipal con Funci\u00f3n de Conocimiento el 12 de julio de 2016, en primera instancia, y por el Juzgado Octavo Penal para Adolescentes con Funci\u00f3n de Conocimiento de Bogot\u00e1 el 27 de julio de 2016, en segunda instancia, dentro del tr\u00e1mite de acci\u00f3n de tutela presentada por la se\u00f1ora Irma Casta\u00f1eda Ram\u00edrez contra la Universidad Distrital Francisco Jos\u00e9 de Caldas.\u00a0 \u00a0<\/p>\n<p>I. ANTECEDENTES \u00a0<\/p>\n<p>1. Hechos relevantes y acci\u00f3n de tutela interpuesta \u00a0<\/p>\n<p>1. La se\u00f1ora Irma Casta\u00f1eda Ram\u00edrez indica que el 27 de abril de 2016, radic\u00f3 ante la Vicerrector\u00eda Administrativa y Financiera de la Universidad Distrital Francisco Jos\u00e9 de Caldas una solicitud de informaci\u00f3n, por la cual requiri\u00f3 que se le entregaran los siguientes documentos:\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>* \u201cCopia \u00edntegra, debidamente foliada, de la carpeta que en esa Vicerrector\u00eda se lleva y que contiene los documentos relacionados con el tr\u00e1mite dado a la problem\u00e1tica surgida con el Jefe de la Oficina Asesora de Asuntos Disciplinarios\u201d\u00a0 \u00a0\u00a0<\/p>\n<p>* \u201cCopia, con sus respectivos soportes, de la recusaci\u00f3n presentada por usted en contra del Jefe de la Oficina Asesora de Control Interno, relacionada con el seguimiento solicitado por m\u00ed al Ente de Control, respecto de las actuaciones administrativas relacionadas con la problem\u00e1tica surgida con el Jefe de la Oficina Asesora de Asuntos Disciplinarios\u201d.\u00a0 \u00a0\u00a0<\/p>\n<p>* \u201cCopia con sus respectivos soportes del acto administrativo, por medio del cual la administraci\u00f3n de la Universidad resuelve la recusaci\u00f3n antes mencionada\u201d.\u00a0 \u00a0\u00a0<\/p>\n<p>* \u201cCopia de cualquier otro documento diferente a los enunciados en los numerales anteriores, por medio del cual el doctor Ra\u00fal1 haya aportado, solicitado, pedido y\/o requerido informaci\u00f3n de cualquier tipo relacionada con mi persona. En caso negativo, certificar lo correspondiente\u201d. \u00a0 \u00a0<\/p>\n<p>2. El mismo d\u00eda, la accionante radic\u00f3 ante la Oficina Asesora de Asuntos Disciplinarios de la Universidad otra solicitud, requiriendo que le fuera entregada copia con su respectiva radicaci\u00f3n, de las demandas de tipo penal y quejas disciplinarias instauradas por el jefe de dicha oficina en contra de la se\u00f1ora Casta\u00f1eda por los delitos de falsa denuncia contra persona determinada, injuria y calumnia, extorsi\u00f3n, infidelidad a los deberes profesionales y por cualquier otro hecho punible y\/o disciplinario.\u00a0 \u00a0<\/p>\n<p>3. Igualmente, la se\u00f1ora Casta\u00f1eda radic\u00f3 similares peticiones ante las Divisiones de Recursos Humanos y de Recursos F\u00edsicos de la Universidad, solicitando a la primera que le otorgara copia del oficio por medio del cual el doctor Ra\u00fal solicit\u00f3 a esa dependencia que se adelantara tr\u00e1mite ante la ARL relacionado con la salud f\u00edsica, mental o psicol\u00f3gica de la accionante y la respuesta otorgada, as\u00ed como copia de cualquier solicitud que el se\u00f1or Ra\u00fal hubiese hecho en relaci\u00f3n con la se\u00f1ora Casta\u00f1eda. Con respecto a la segunda Divisi\u00f3n, la actora requiri\u00f3 copia del oficio por el cual el se\u00f1or Ra\u00fal \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0solicit\u00f3 copia de los videos de las c\u00e1maras de seguridad ubicadas en el octavo piso de las oficinas de la Universidad, con la respuesta correspondiente.\u00a0 \u00a0<\/p>\n<p>4. La Vicerrector\u00eda de la Universidad entreg\u00f3 una informaci\u00f3n que la accionante consider\u00f3 incompleta, por lo que dirigi\u00f3 un correo electr\u00f3nico el 11 de mayo de 2016 solicitando que se completara lo solicitado y que entregara copia de los siguientes documentos:\u00a0 \u00a0<\/p>\n<p>&#8211; Copia de las grabaciones de las dos reuniones que sostuvimos en su despacho durante el mes de febrero de 2016.\u00a0 \u00a0<\/p>\n<p>&#8211; Copia de la certificaci\u00f3n de cumplimiento de actividades firmada por el doctor Camilo Bustos como Jefe Encargado de la Oficina Asesora de Asuntos Disciplinarios durante los primeros d\u00edas del mes de febrero de 2016.\u00a0 \u00a0<\/p>\n<p>&#8211; Copia del oficio OAD \u2013 468 del 5 de abril de 2016, firmado por el Jefe de la Oficina Asesora de Asuntos Disciplinarios, junto con sus anexos \u2013 correos electr\u00f3nicos y dem\u00e1s, el cual fue utilizado para soportar la recusaci\u00f3n al Jefe de la Oficina Asesora de Control Interno.\u00a0 \u00a0<\/p>\n<p>&#8211; Copia del oficio OAD \u2013 562 del 21 de febrero de 2015, dirigido al Vicerrector por el Jefe de la Oficina Asesora de Asuntos Disciplinarios, comunic\u00e1ndole que ha instaurado denuncia penal en contra de la accionante por los delitos de falsa denuncia contra persona determinada, injuria y calumnia y otros.\u00a0 \u00a0<\/p>\n<p>5. Como respuesta, la Vicerrector\u00eda manifest\u00f3 que ya le hab\u00edan enviado a la solicitante toda la documentaci\u00f3n que reposaba en su carpeta y que los documentos relacionados con la Oficina Asesora de Asuntos Disciplinarios deb\u00edan ser solicitados ante la misma dependencia. Frente a esta respuesta, la se\u00f1ora Casta\u00f1eda resalta en su escrito de tutela que la informaci\u00f3n solicitada hab\u00eda sido enviada a la Vicerrector\u00eda o hab\u00eda sido generada en ella.\u00a0 \u00a0<\/p>\n<p>Concretamente, la se\u00f1ora Casta\u00f1eda reprocha que las grabaciones de las reuniones en el Despacho de la Vicerrector\u00eda le fueron negadas pero s\u00ed fueron entregadas al Jefe de la Oficina Asesora de Asuntos Disciplinarios y que la certificaci\u00f3n de cumplimiento de actividades fue remitida al Vicerrector Administrativo y Financiero y, sin embargo, no le fue entregada. En el mismo sentido, la accionante indica que los oficios OAD \u2013 468 del 5 de abril de 2016 y OAD \u2013 562 del 21 de febrero de 2015 fueron firmados por el Jefe de la Oficina Asesora de Asuntos Disciplinarios y enviados a la Vicerrector\u00eda Administrativa y Financiera, por lo que, en su concepto, deben reposar en los archivos de esta \u00faltima dependencia y deben ser entregados por referirse a ella.\u00a0 \u00a0<\/p>\n<p>6. En cuanto a la Oficina Asesora de Asuntos Disciplinarios, la accionante manifiesta que le respondieron que no pod\u00edan entregar la informaci\u00f3n solicitada porque esta \u201cse encuentra amparada por la reserva del sumario\u201d. Al respecto, afirma que esos datos s\u00ed han sido entregadas al Vicerrector Administrativo y Financiero, que no tiene parte en el asunto, y le han sido negados a ella, a pesar de que se refieren a denuncias interpuestas en su contra. As\u00ed mismo, la se\u00f1ora Casta\u00f1eda aclara que la mencionada Oficina no tiene competencia para investigarla en vista de que su vinculaci\u00f3n con la Universidad Distrital es a trav\u00e9s de un contrato de prestaci\u00f3n de servicios ni tiene permitido retener o solicitar informaci\u00f3n de la actora.\u00a0 \u00a0<\/p>\n<p>7. Sobre la informaci\u00f3n solicitada a la Divisi\u00f3n de Recursos Humanos, la se\u00f1ora Casta\u00f1eda se\u00f1ala que su petici\u00f3n fue contestada de manera parcial pues no se le proporcion\u00f3 copia del oficio OAD \u2013 437 del 28 de marzo de 2016. De dicho documento, el Jefe de la Divisi\u00f3n \u201cdice que fue devuelto a la Oficina de origen, o sea a la Oficina Asesora de Asuntos Disciplinarios y este \u00faltimo, a su vez, contradice a la Jefe de la Divisi\u00f3n de Recursos Humanos, negando su autor\u00eda\u201d. Por otra parte, se\u00f1ala que el Jefe de la Divisi\u00f3n de Recursos F\u00edsicos, tampoco entreg\u00f3 la informaci\u00f3n y, por el contrario, remiti\u00f3 la solicitud de la accionante a la Oficina Asesora de Asuntos Disciplinarios, la cual se resiste a entregarla bajo el argumento de que son documentos reservados.\u00a0 \u00a0<\/p>\n<p>8. Por la negativa de las mencionadas dependencias de entregar la informaci\u00f3n solicitada, la accionante considera que se han vulnerado sus derechos fundamentales de petici\u00f3n y de acceso a la informaci\u00f3n p\u00fablica. En consecuencia, solicita al juez constitucional que proceda al amparo de esas garant\u00edas fundamentales y que ordene a la entidad accionada que entregue la totalidad de la informaci\u00f3n solicitada dentro de las 48 horas siguientes a la notificaci\u00f3n de la sentencia favorable a sus pretensiones.\u00a0 \u00a0<\/p>\n<p>2. Pruebas relevantes aportadas con la acci\u00f3n de tutela \u00a0<\/p>\n<p>A su escrito de tutela, el accionante adjunt\u00f3 los siguientes documentos, con el prop\u00f3sito de que fuesen tenidos como prueba durante el tr\u00e1mite correspondiente:\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Copia de escrito de solicitud de informaci\u00f3n dirigido por la se\u00f1ora Irma Casta\u00f1eda al Vicerrector Administrativo y Financiero de la Universidad Distrital (26 de abril de 2016).\u00a0 \u00a0\u00a0<\/p>\n<p>2. Copia de escrito de solicitud de informaci\u00f3n dirigido por la se\u00f1ora Irma Casta\u00f1eda al Jefe de la Oficina Asesora de Asuntos Disciplinarios (27 de abril de 2016).\u00a0 \u00a0\u00a0<\/p>\n<p>3. Copia de escrito de solicitud de informaci\u00f3n dirigido por la se\u00f1ora Irma Casta\u00f1eda al Jefe de Divisi\u00f3n de Recursos Humanos (27 de abril de 2016).\u00a0 \u00a0\u00a0<\/p>\n<p>5. Copia de correo electr\u00f3nico por el cual la se\u00f1ora Casta\u00f1eda solicit\u00f3 complementaci\u00f3n de informaci\u00f3n al se\u00f1or Vicerrector Administrativo y Financiero (11 de mayo de 2016).\u00a0 \u00a0\u00a0<\/p>\n<p>6. Copia de la respuesta emitida por el Jefe de la Oficina Asesora de Asuntos Disciplinarios (27 de abril de 2016), en la cual se informa que \u201cen cuanto a su solicitud, a trav\u00e9s de la cual solicita copia de las denuncias penales y disciplinarias que se han promovido en su contra y donde el suscrito obra como denunciante, (\u2026) me permito informarle que dicha informaci\u00f3n (sic) se encuentra amparada por la reserva del sumario; raz\u00f3n por la cual su solicitud se rechaza\u201d.\u00a0 \u00a0\u00a0<\/p>\n<p>7. Copia de la respuesta \u00a0del 5 de mayo de 2016, emitida por el Jefe de la Divisi\u00f3n de Recursos Humanos, en la cual se indica que la solicitud de la se\u00f1ora Casta\u00f1eda fue trasladada a la Oficina de Asuntos Disciplinarios, \u201ctoda vez que el oficio OAD 437 de marzo 28 de 2016 fue producido en dicho despacho y el mensajero de la Divisi\u00f3n inform\u00f3 que al radicar la respuesta llevaba adjunto la solicitud\u201d, as\u00ed como que \u201cactualmente no tenemos evidencia de que se haya solicitado m\u00e1s informaci\u00f3n a su nombre\u201d.\u00a0 \u00a0\u00a0<\/p>\n<p>8. Copia de respuesta emitida por el se\u00f1or Ra\u00fal del 06 de mayo de 2016, Jefe de la Oficina Asesora de Asuntos Disciplinarios de la Universidad, en la cual le inform\u00f3 a la Jefe de Divisi\u00f3n de Recursos Humanos que no hab\u00eda solicitado tr\u00e1mite alguno ante la ARL para tratar presuntos problemas de salud de la se\u00f1ora Casta\u00f1eda. Igualmente, indic\u00f3 que \u201cla informaci\u00f3n que he obtenido de la Divisi\u00f3n, ha sido incorporada a los m\u00faltiples procesos penales y disciplinarios que cursan en contra de la se\u00f1ora Casta\u00f1eda Ram\u00edrez, raz\u00f3n por la cual se encuentran amparados por la reserva del sumario y, en mi calidad de v\u00edctima, no estoy en la obligaci\u00f3n de entregarlos (\u2026)\u201d.\u00a0 \u00a0\u00a0<\/p>\n<p>9. Copia de oficio dirigido a la Jefa de la Divisi\u00f3n el 13 de junio de 2016, por parte del Jefe de la Oficina Asesora de Asuntos Disciplinarios en el cual informa que no puede acceder a la petici\u00f3n de entregar la documentaci\u00f3n que el se\u00f1or Ra\u00fal pidi\u00f3 a la ARL sobre el estado de salud de la accionante, por dos razones: primero, de acuerdo con el se\u00f1or Ra\u00fal, \u00e9l nunca solicit\u00f3 ese tipo de informaci\u00f3n y, segundo, los documentos que \u00e9l hab\u00eda solicitado a la Divisi\u00f3n se encuentran amparados por la reserva del sumario, de forma que la se\u00f1ora Casta\u00f1eda s\u00f3lo podr\u00eda tener acceso a la informaci\u00f3n una vez adquiriera la calidad de indagada o investigada en los procesos respectivos.\u00a0 \u00a0\u00a0<\/p>\n<p>10. Copia de oficio del 10 de mayo de 2016, por el cual el Jefe de la Divisi\u00f3n de Recursos F\u00edsicos le responde a la se\u00f1ora Irma Casta\u00f1eda indicando que no dispon\u00eda de los videos de las c\u00e1maras de vigilancia y que en esa dependencia no reposaban solicitudes por parte del Dr. Ra\u00fal que la involucraran a ella como contratista y\/o como persona natural.\u00a0 \u00a0\u00a0<\/p>\n<p>11. Copia de correo electr\u00f3nico enviado por la se\u00f1ora Casta\u00f1eda el 11 de mayo de 2016 al Jefe de Divisi\u00f3n de Recursos Humanos en el cual insiste en la solicitud de informaci\u00f3n, aclarando que no requiere los videos de vigilancia sino copia del oficio por el cual el Jefe de la Oficina de Asuntos Disciplinarios solicit\u00f3 los mismos.\u00a0 \u00a0\u00a0<\/p>\n<p>12. Como respuesta al e \u2013 mail anterior, el Jefe de la Divisi\u00f3n de Recursos F\u00edsicos indic\u00f3, el 13 de junio de 2016, que la solicitud hab\u00eda sido dirigida al Jefe de la Oficina Asesora de Asuntos Disciplinarios el 16 de mayo de 2016 para que fuera resuelta.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Oficina de Asuntos Disciplinarios emiti\u00f3 la respuesta solicitada el 13 de junio de 2016, indicando que si bien el Jefe de esa oficina hab\u00eda solicitado copia de las cintas de vigilancia, \u201ca la fecha no han sido remitidas por la compa\u00f1\u00eda de vigilancia, las mismas ten\u00edan como fin indagar sobre la presunta amistad que exist\u00eda entre la peticionaria y el se\u00f1or Vergara Vergara, (\u2026) lo que pudo, al parecer, repercutir en la sustanciaci\u00f3n de los expedientes disciplinarios respectivos (\u2026) As\u00ed las cosas, se inform\u00f3 a la Fiscal\u00eda General de la Naci\u00f3n y al Consejo Superior de la Judicatura sobre el proceder presuntamente irregular comportado por la profesional del derecho. Una vez se suministren copia de las grabaciones, en especial la del 02 de febrero de 2016, ser\u00e1n aportadas como prueba a los procesos judiciales y administrativos del caso\u201d.\u00a0 \u00a0 \u00a0<\/p>\n<p>4. Respuesta de las entidades accionadas \u00a0<\/p>\n<p>1. Mediante escrito presentado al Juzgado Veinticinco Penal Municipal con Funci\u00f3n de Conocimiento el 01 de julio de 2016, el se\u00f1or Ra\u00fal, en su calidad de Jefe de la Oficina Asesora de Asuntos Disciplinarios de la Universidad Distrital, inform\u00f3 lo siguiente: primero, que fue v\u00edctima de una \u201cestrategia de desprestigio orquestada por varios funcionarios\u201d de la Universidad, en el periodo de vacaciones que disfrut\u00f3 entre el 18 de enero y el 08 de febrero de 2016. En ese sentido, acus\u00f3 a la se\u00f1ora Irma Casta\u00f1eda de haber participado en dicha campa\u00f1a, que tuvo por objeto lograr el relevo del cargo del se\u00f1or Ra\u00fal una vez se reintegrara a sus labores. As\u00ed mismo, afirm\u00f3 que ten\u00eda conocimiento de que la accionante hab\u00eda manipulado los procesos disciplinarios a su cargo en favor de varios funcionarios y ex \u2013 funcionarios del claustro universitario, por lo que procedi\u00f3 a formular las respectivas denuncias ante la Fiscal\u00eda General de la Naci\u00f3n y el Consejo Superior de la Judicatura.\u00a0 \u00a0<\/p>\n<p>Con relaci\u00f3n a la acci\u00f3n de tutela interpuesta por la se\u00f1ora Casta\u00f1eda, el se\u00f1or Ra\u00fal afirm\u00f3 que su oficina hab\u00eda contestado de manera completa y oportuna las solicitudes radicadas por la accionante, excepto en lo atinente a los documentos que reposan en el Consejo Superior de la Judicatura y en la Fiscal\u00eda General de la Naci\u00f3n y que est\u00e1n cubiertos por la reserva del sumario. En consecuencia, solicit\u00f3 al juez de conocimiento que desestimara la acci\u00f3n de referencia, al considerar que no se vulneraron los derechos fundamentales de la se\u00f1ora Casta\u00f1eda. Para apoyar su pretensi\u00f3n, adjunt\u00f3 los siguientes documentos:\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>* Copia de oficio del 01 de julio de 2016, por el cual el se\u00f1or Ra\u00fal remiti\u00f3 al Consejo Superior de la Judicatura la petici\u00f3n elevada por la se\u00f1ora Casta\u00f1eda para obtener copia de la queja disciplinaria instaurada por el se\u00f1or Ra\u00fal.\u00a0 \u00a0\u00a0<\/p>\n<p>* Copia de oficio del 01 de julio de 2016, por el cual el se\u00f1or Ra\u00fal manifiesta a la se\u00f1ora Casta\u00f1eda que su derecho de petici\u00f3n del 26 de abril de 2016 fue respondido el d\u00eda 27 del mismo mes. En ese mismo oficio, pone de presente su sorpresa por la presentaci\u00f3n de la acci\u00f3n de tutela de referencia, al considerar que hab\u00eda respondido completamente y de fondo, sin objeciones por parte de la se\u00f1ora Casta\u00f1eda. Igualmente, inform\u00f3 a la accionante que los otros documentos deb\u00eda solicitarlos a la Fiscal\u00eda General de la Naci\u00f3n o ante el Consejo Superior de la Judicatura.\u00a0 \u00a0\u00a0<\/p>\n<p>* Copia de las respuestas producidas por la Oficina Asesora de Asuntos Disciplinarios ante las peticiones de la se\u00f1ora Casta\u00f1eda, que ya obraban dentro de las pruebas presentadas por la accionante.\u00a0 \u00a0\u00a0<\/p>\n<p>* Copia de oficio del 01 de julio de 2016, por el cual el se\u00f1or Ra\u00fal remiti\u00f3 a la Fiscal\u00eda General de la Naci\u00f3n la petici\u00f3n elevada por la se\u00f1ora Casta\u00f1eda para obtener copia de las denuncias interpuestas en su contra por el se\u00f1or Ra\u00fal. \u00a0 \u00a0<\/p>\n<p>\u00a02. A trav\u00e9s de un escrito presentado el 5 de julio de 2016, el Jefe de la Oficina Asesora Jur\u00eddica de la Universidad, en representaci\u00f3n judicial de la misma, se\u00f1al\u00f3 que era cierto que la accionante hab\u00eda hecho las solicitudes referenciadas en el escrito de tutela, pero que estas, contrario a lo sostenido por la accionante, hab\u00edan sido resueltas oportuna y completamente. En ese sentido, aclar\u00f3 que de las cuatro peticiones presentadas por la se\u00f1ora Casta\u00f1eda (a la Vicerrector\u00eda Administrativa y Financiera, a la Oficina Asesora de Asuntos Disciplinarios, a la Divisi\u00f3n de Recursos Humanos y a la de Recursos F\u00edsicos), estas fueron respondidas as\u00ed: i) la elevada a la Vicerrector\u00eda fue resuelta mediante oficio del 3 de mayo de 2016, junto con el cual se entreg\u00f3 \u201ccopia de toda la carpeta que obra en poder de la dependencia\u201d; ii) las interpuestas en la Oficina Asesora de Asuntos Disciplinarios, se respondieron entre el 27 de abril y el 01 de julio de 2016.\u00a0 \u00a0<\/p>\n<p>Por su parte, las peticiones radicadas en iii) la Divisi\u00f3n de Recursos Humanos, se respondieron a trav\u00e9s de oficio de fecha 01 de julio de 2016, mientras que la enviada a iv) la Divisi\u00f3n de Recursos F\u00edsicos, se solucionaron a trav\u00e9s del oficio DRF \u2013 0451 de 2016. As\u00ed las cosas, la Universidad sostiene que no le asiste raz\u00f3n a la accionante en lo que ata\u00f1e a la presunta vulneraci\u00f3n de sus derechos fundamentales, dado que se le respondieron todos sus requerimientos. Para soportar sus afirmaciones, el Jefe de la Oficina Asesora Jur\u00eddica adjunt\u00f3 las copias de los oficios mencionados.\u00a0 \u00a0<\/p>\n<p>Posteriormente, mediante un escrito del 05 de julio de 2016, el Jefe de la Oficina Asesora Jur\u00eddica complement\u00f3 la contestaci\u00f3n suministrada, indicando que la Vicerrector\u00eda Administrativa y Financiera contest\u00f3 el requerimiento de la se\u00f1ora Casta\u00f1eda el 05 de mayo de ese a\u00f1o, haci\u00e9ndose entrega de copias \u00edntegras de los \u201c117 folios que integraban la carpeta total que obraba en poder de la Vicerrector\u00eda Administrativa y Financiera y de copia de las recusaciones de fechas 08 de marzo y 05 de abril de 2016, como de copia de la Resoluci\u00f3n por medio de la cual se acepta una recusaci\u00f3n No. 181 de 2016 (sic)\u201d. Finalmente, el Jefe de la Oficina Asesora Jur\u00eddica adjunt\u00f3 copia de los correos electr\u00f3nicos por medio de los cuales la Fiscal\u00eda General de la Naci\u00f3n y el Consejo Superior de la Judicatura avocaron conocimiento de la petici\u00f3n elevada por la accionante, con fecha del 05 de mayo de 2016. \u00a0<\/p>\n<p>4. Decisiones judiciales objeto de revisi\u00f3n \u00a0<\/p>\n<p>A trav\u00e9s de sentencia proferida el 12 de julio de 2016, el Juzgado Veinticinco Penal Municipal con Funci\u00f3n de Conocimiento resolvi\u00f3 la acci\u00f3n de referencia en primera instancia, declarando improcedente la solicitud de amparo. Para sustentar su posici\u00f3n, el Juzgado realiz\u00f3 varias referencias al contenido del derecho fundamental de petici\u00f3n y, posteriormente, hizo una reconstrucci\u00f3n de las peticiones hechas por la accionante y las respuestas recibidas. Analizando las pruebas recaudadas, el Juzgado indic\u00f3 que la accionante contaba con otros mecanismos judiciales ordinarios para lograr el levantamiento de la reserva de los documentos que la tienen o participar en los procesos penales o disciplinarios que se le siguen. As\u00ed, al considerar que la acci\u00f3n no cumpli\u00f3 con el requisito de subsidiariedad, procedi\u00f3 a declarar la improcedencia.\u00a0 \u00a0<\/p>\n<p>La anterior decisi\u00f3n fue impugnada por la accionante indicando que, contrario a lo sostenido por el Juez de instancia, ella no estaba solicitando informaci\u00f3n reservada sino documentos relacionados con sus propias actividades contractuales o personales. Por otro lado, resalt\u00f3 que el juez no evidenci\u00f3 la existencia de una investigaci\u00f3n penal o disciplinaria en su contra, por lo que no puede hablarse realmente de la existencia de documentos bajo reserva. As\u00ed, resalt\u00f3 que \u201cel hecho de que de forma extempor\u00e1nea, con fecha 1 de julio de 2016, y s\u00f3lo luego de que fuera notificada la tutela, supuestamente remitiera mi derecho de petici\u00f3n al Consejo Superior de la Judicatura y a la Fiscal\u00eda General de la Naci\u00f3n (\u2026) s\u00f3lo demuestra que no se atendi\u00f3 en debida forma mi solicitud\u201d. Por ende, solicit\u00f3 que el juez de segunda instancia se pronunciara sobre la necesidad de que la entidad accionada le entregara los documentos que a\u00fan no hab\u00edan sido puestos a su disposici\u00f3n.\u00a0 \u00a0<\/p>\n<p>El se\u00f1or Ra\u00fal tambi\u00e9n intervino en el tr\u00e1mite de segunda instancia, reiterando los argumentos presentados en la contestaci\u00f3n original y agregando que la Fiscal\u00eda General de la Naci\u00f3n y el Consejo Superior de la Judicatura ya hab\u00edan dado respuesta a las peticiones elevadas por la accionante, a trav\u00e9s de los oficios No. 0124 MDEC (15 de julio de 2016) del Consejo Superior y del No. 005760 (18 de julio de 2016), emitido por la Fiscal\u00eda, con posterioridad al fallo de primera instancia. En ellos, se indic\u00f3 que ambas entidades hab\u00edan iniciado investigaciones en contra de la se\u00f1ora Irma Casta\u00f1eda y se mencionaron los radicados de dichas indagaciones judiciales. Por ende, concluy\u00f3 el interviniente, la accionante puede acercarse a las mencionadas entidades con el fin de obtener la informaci\u00f3n que requiere.\u00a0 \u00a0<\/p>\n<p>Conociendo sobre la impugnaci\u00f3n, el Juzgado Octavo Penal para Adolescentes con Funci\u00f3n de Conocimiento de Bogot\u00e1 decidi\u00f3 confirmar el fallo cuestionado mediante sentencia del 24 de agosto de 2016 considerando, por un lado, que la accionante podr\u00eda acudir ante la Jurisdicci\u00f3n Contencioso Administrativa para solicitar la entrega de los documentos y, por otro, que \u201csi bien es cierto los documentos solicitados por la se\u00f1ora Irma Casta\u00f1eda no se encuentran debidamente estipulados en la Ley y en la Constituci\u00f3n como objeto de reserva del sumario, ello no significa que en la actualidad no hayan adquirido tal condici\u00f3n\u201d, en vista de que en ese momento ya hab\u00edan sido incorporados a investigaciones judiciales adelantadas por el Consejo Superior de la Judicatura y por la Fiscal\u00eda General de la Naci\u00f3n.\u00a0 \u00a0<\/p>\n<p>5. Tr\u00e1mite adelantado ante la Corte Constitucional \u00a0<\/p>\n<p>1. En cumplimiento de lo dispuesto en el Decreto Ley 2591 de 1991, el expediente fue remitido a esta Corporaci\u00f3n para su eventual revisi\u00f3n. La Sala de Selecci\u00f3n de Tutelas N\u00famero Once, mediante auto del 17 de noviembre de 2016, decidi\u00f3 seleccionar para revisi\u00f3n el expediente de referencia, luego de que la Magistrada Gloria Stella Ortiz Delgado radicara un escrito de insistencia de revisi\u00f3n del mismo.\u00a0 \u00a0<\/p>\n<p>En su escrito, la Magistrada indic\u00f3 que, en su concepto, el caso deb\u00eda ser revisado por esta Corporaci\u00f3n en tanto que sirve para sentar jurisprudencia sobre si el recurso de insistencia contra la decisi\u00f3n que rechace una petici\u00f3n de informaci\u00f3n, establecido en los art\u00edculos 25 y 26 de la Ley 1755 de 2015, es id\u00f3neo para cuestionar qui\u00e9n tiene que dar respuesta a una solicitud. En ese sentido, la Magistrada resalt\u00f3 que \u201cel caso podr\u00eda presentar un problema jur\u00eddico de fondo que va m\u00e1s all\u00e1 de evaluar si la informaci\u00f3n pedida est\u00e1 o no sujeta a reserva legal, motivo por el cual el mecanismo judicial que en principio es id\u00f3neo para resolver el asunto, podr\u00eda no serlo ante las particularidades del caso\u201d.\u00a0 \u00a0<\/p>\n<p>Por otra parte, la togada se\u00f1al\u00f3 que la Corte deber\u00eda evaluar la posibilidad de que a la accionante le haya sido vulnerado, adem\u00e1s del derecho de petici\u00f3n, el derecho fundamental al debido proceso \u201cporque la accionante tiene conocimiento de que se adelantan distintas actuaciones en su contra como consecuencia de haber denunciado al se\u00f1or Ra\u00fal por acoso sexual, y al indagar sobre tales acciones, quien responde es el mismo denunciado\u201d. A juicio de la Magistrada, el caso tiene especial inter\u00e9s en vista de que involucra una acusaci\u00f3n por abuso sexual, \u201cel cual comporta la intimidaci\u00f3n, cosificaci\u00f3n y violencia psicol\u00f3gica contra la mujer\u201d. \u00a0 \u00a0<\/p>\n<p>2. Durante \u00a0el \u00a0tr\u00e1mite de \u00a0revisi\u00f3n \u00a0se recibieron \u00a0sendos escritos \u00a0 presentados por \u00a0el \u00a0se\u00f1or \u00a0Ra\u00fal. \u00a0En el primero, \u00a0dirigido a la Magistrada \u00a0Ortiz Delgado, \u00a0el \u00a0interviniente puso de presente que en la acci\u00f3n de tutela la se\u00f1ora Casta\u00f1eda no hizo referencia alguna al acoso sexual del que presuntamente fue v\u00edctima por lo que eso no podr\u00eda ser tenido en cuenta para fallar el asunto, que est\u00e1 relacionado con la presunta vulneraci\u00f3n del derecho fundamental de petici\u00f3n. En relaci\u00f3n con eso, el interviniente resalt\u00f3 que, para los d\u00edas en los que la se\u00f1ora Casta\u00f1eda fue presuntamente v\u00edctima de acoso sexual, \u00e9ste se encontraba en vacaciones y, en todo caso, no era supervisor ni jefe de la se\u00f1ora Irma Casta\u00f1eda.\u00a0 \u00a0<\/p>\n<p>Posteriormente, \u00a0el 08 de Febrero de 2017, \u00a0el se\u00f1or Ra\u00fal \u00a0alleg\u00f3 otro escrito con el objetivo de \u201cbrindar informaci\u00f3n que permita el esclarecimiento de los hechos y derechos que se han puesto en consideraci\u00f3n\u201d. Con esa intenci\u00f3n en mente, procedi\u00f3 a hacer un recuento de los hechos para \u00a0luego indicar que, contrario \u00a0a lo sostenido por la accionante, las solicitudes elevadas por ella hab\u00edan sido atendida de manera completa y oportuna pero que no se le hab\u00eda otorgado todo lo pedido, lo cual no resulta contrario a la ley ni a la jurisprudencia. En ese sentido, resalt\u00f3 que, sin tener el deber de hacerlo, la Universidad remiti\u00f3 a las autoridades competentes (es decir, al Consejo Superior de la Judicatura y a la Fiscal\u00eda General), las peticiones de la se\u00f1ora Casta\u00f1eda.\u00a0 \u00a0<\/p>\n<p>Por otra parte, el se\u00f1or Ra\u00fal mencion\u00f3 que la accionante no agot\u00f3 los mecanismos ordinarios de defensa judicial; concretamente, el recurso de insistencia contenido en los art\u00edculos 25 y 26 de la Ley Estatutaria 1755 de 2015 y reiter\u00f3 que la informaci\u00f3n requerida se encontraba bajo reserva legal, la cual no pod\u00eda ser levantada por las autoridades universitarias. Finalmente, el interviniente defendi\u00f3 que en el caso de referencia no pod\u00eda aplicarse un enfoque diferencial por raz\u00f3n del g\u00e9nero, en vista de que la accionante no hab\u00eda hecho referencia a sus denuncias por acoso sexual en el escrito de tutela y, adem\u00e1s, los presuntos hechos constitutivos de abuso de autoridad, maltrato verbal o psicol\u00f3gico, extralimitaci\u00f3n de funciones y acoso laboral, \u201cson actualmente objeto de investigaci\u00f3n en las instancias disciplinarias y penales correspondientes\u201d, por lo que no podr\u00eda la Corte pronunciarse sobre asuntos que son objeto de una controversia actual.\u00a0 \u00a0<\/p>\n<p>i). Con respecto a la solicitud de que le fueran entregadas las quejas y denuncias disciplinarias y penales interpuestas en su contra por el Jefe de la Oficina de Asuntos Disciplinarios, la Universidad sostuvo su posici\u00f3n de que estos documentos son objeto de reserva sumarial y, por ende, no pueden ser entregados.\u00a0 \u00a0<\/p>\n<p>ii) Reiter\u00f3 que, contrario a lo sostenido por la accionante, el Oficio OAD \u2013 437 del 28 de marzo de 2017 no contiene una solicitud por parte del Jefe de la Oficina de Asuntos Disciplinarios para que se le prestara a la se\u00f1ora Casta\u00f1eda un tratamiento psiqui\u00e1trico, sino que se refiere a una petici\u00f3n por la cual el se\u00f1or Ra\u00fal le solicit\u00f3 a la Jefatura de Recursos Humanos que informara si personal adscrito a su despacho hab\u00eda solicitado acompa\u00f1amiento psiqui\u00e1trico o psicol\u00f3gico durante los a\u00f1os 2015 y 2016.\u00a0 \u00a0<\/p>\n<p>iii) \u00a0Sobre la petici\u00f3n por la cual la accionante pidi\u00f3 una copia de la solicitud hecha por el Jefe de Asuntos Disciplinarios a la Divisi\u00f3n de Recursos F\u00edsicos requiriendo algunas grabaciones f\u00edlmicas, \u201chay que decir que si bien es cierto que inicialmente se neg\u00f3 el acceso a esa informaci\u00f3n por considerarla de inter\u00e9s meramente institucional, una vez la Universidad fue notificada de la acci\u00f3n de tutela en comento procedi\u00f3 a remitirle a la solicitante la copia del oficio requerido\u201d.\u00a0 \u00a0<\/p>\n<p>Finalmente, la Universidad adjunt\u00f3 a su oficio un sobre sellado en el que suministraron copia de la denuncia penal y la queja disciplinaria que fueron interpuestas en contra de la accionante, con el fin de que fuese la Corte la que determinara el destino de dicha documentaci\u00f3n.\u00a0 \u00a0<\/p>\n<p>II. CONSIDERACIONES Y FUNDAMENTOS\u00a0 \u00a0<\/p>\n<p>Problema jur\u00eddico y fundamento de la decisi\u00f3n\u00a0 \u00a0<\/p>\n<p>1. La se\u00f1ora Irma Casta\u00f1eda fue contratista de la Universidad Distrital Francisco Jos\u00e9 de Caldas. Durante el desarrollo de sus obligaciones, entr\u00f3 en controversias con el entonces Jefe de la Oficina Asesora de Asuntos Disciplinarios del claustro, quien interpuso denuncias en contra de la accionante y solicit\u00f3 informaci\u00f3n sobre ella en otras dependencias de la Universidad. Al enterarse de esta situaci\u00f3n, la se\u00f1ora Casta\u00f1eda requiri\u00f3 a esas dependencias que le fueran entregados los oficios a trav\u00e9s de los cuales el Jefe de la Oficina pidi\u00f3 la informaci\u00f3n, as\u00ed como otros documentos relacionados con su periodo de servicios en la entidad educativa.\u00a0 \u00a0<\/p>\n<p>Las peticiones de la se\u00f1ora Casta\u00f1eda fueron respondidas por las distintas dependencias, entreg\u00e1ndole copia de varios documentos, pero remiti\u00e9ndola a la Oficina de Asuntos Disciplinarios para obtener aquellos que hab\u00edan sido radicados por el Jefe de dicha oficina. A su vez, el Jefe de esa Oficina le inform\u00f3 a la accionante que los documentos que faltaban no pod\u00edan ser entregados, en vista de que hac\u00edan parte de investigaciones judiciales iniciadas ante el Consejo Superior de la Judicatura y la Fiscal\u00eda General de la Naci\u00f3n y, por ende, se encuentran cubiertos por la reserva del sumario. Ante esta situaci\u00f3n, la accionante consider\u00f3 vulnerados sus derechos fundamentales de petici\u00f3n y de acceso a la informaci\u00f3n por lo cual interpuso la acci\u00f3n de tutela de referencia, con el fin de que el juez constitucional le ordene a la accionada la entrega de los documentos faltantes.\u00a0 \u00a0<\/p>\n<p>2. As\u00ed las cosas, el problema jur\u00eddico que la Sala deber\u00e1 resolver se centra en determinar si el derecho fundamental de petici\u00f3n de la accionante se vio vulnerado ante la negativa de las autoridades universitarias de entregarle ciertos documentos, bajo el argumento de que estos estaban cubiertos por la reserva del sumario. Sin embargo, previo a resolver este asunto, se deber\u00e1 determinar si la acci\u00f3n es procedente en t\u00e9rminos formales para as\u00ed poder establecer si la Corte tiene competencia para fallar de fondo. Para eso, se har\u00e1 referencia al mecanismo judicial contemplado en la Ley 1755 de 2015 y su relaci\u00f3n con el principio de subsidiariedad para luego evaluar el caso concreto.\u00a0 \u00a0<\/p>\n<p>Ley Estatutaria del Derecho Fundamental de Petici\u00f3n y el principio de subsidiariedad.\u00a0 \u00a0<\/p>\n<p>3. El art\u00edculo 23 de la Constituci\u00f3n Pol\u00edtica de 1991 establece que \u201cToda persona tiene derecho a presentar peticiones respetuosas a las autoridades por motivos de inter\u00e9s general o particular y a obtener pronta resoluci\u00f3n. El legislador podr\u00e1 reglamentar su ejercicio ante organizaciones privadas para garantizar los derechos fundamentales\u201d, con lo cual qued\u00f3 instituido el denominado derecho fundamental de petici\u00f3n y de acceso a la informaci\u00f3n. En desarrollo de esta garant\u00eda, el legislador procedi\u00f3 a ejercer su facultad regulatoria a trav\u00e9s de la Ley Estatutaria 1755 de 2015, en la cual se establecieron los principios y mecanismos para el ejercicio de este derecho por parte de los ciudadanos y las obligaciones de las autoridades a la hora de dar respuesta a dichos requerimientos.\u00a0 \u00a0<\/p>\n<p>4. Una de las innovaciones m\u00e1s importantes contenidas en la Ley Estatutaria se refiere a la regulaci\u00f3n de aquellos casos en los cuales las personas solicitan informaci\u00f3n que las autoridades consideran que est\u00e1 bajo reserva pero a la que los ciudadanos insisten en acceder. Estos supuestos aparecen regulados en los art\u00edculos 25 y 36 de la Ley, que establecen lo siguiente:\u00a0 \u00a0<\/p>\n<p>\u201cArt\u00edculo\u00a025.\u00a0Rechazo de las peticiones de informaci\u00f3n por motivo de reserva.\u00a0Toda decisi\u00f3n que rechace la petici\u00f3n de informaciones o documentos ser\u00e1 motivada, indicar\u00e1 en forma precisa las disposiciones legales que impiden la entrega de informaci\u00f3n o documentos pertinentes y deber\u00e1 notificarse al peticionario. Contra la decisi\u00f3n que rechace la petici\u00f3n de informaciones o documentos por motivos de reserva legal, no procede recurso alguno, salvo lo previsto en el art\u00edculo siguiente. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>La restricci\u00f3n por reserva legal no se extender\u00e1 a otras piezas del respectivo expediente o actuaci\u00f3n que no est\u00e9n cubiertas por ella. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Art\u00edculo\u00a026.\u00a0Insistencia del solicitante en caso de reserva.\u00a0Si la persona interesada insistiere en su petici\u00f3n de informaci\u00f3n o de documentos ante la autoridad que invoca la reserva, corresponder\u00e1 al Tribunal Administrativo con jurisdicci\u00f3n en el lugar donde se encuentren los documentos, si se trata de autoridades nacionales, departamentales o del Distrito Capital de Bogot\u00e1, o al juez administrativo si se trata de autoridades distritales y municipales decidir en \u00fanica instancia si se niega o se acepta, total o parcialmente la petici\u00f3n formulada. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Para ello, el funcionario respectivo enviar\u00e1 la documentaci\u00f3n correspondiente al tribunal o al juez administrativo, el cual decidir\u00e1 dentro de los diez (10) d\u00edas siguientes. Este t\u00e9rmino se interrumpir\u00e1 en los siguientes casos: \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>1. Cuando el tribunal o el juez administrativo solicite copia o fotocopia de los documentos sobre cuya divulgaci\u00f3n deba decidir, o cualquier otra informaci\u00f3n que requieran, y hasta la fecha en la cual las reciba oficialmente. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>2. Cuando la autoridad solicite, a la secci\u00f3n del Consejo de Estado que el reglamento disponga, asumir conocimiento del asunto en atenci\u00f3n a su importancia jur\u00eddica o con el objeto de unificar criterios sobre el tema. Si al cabo de cinco (5) d\u00edas la secci\u00f3n guarda silencio, o decide no avocar conocimiento, la actuaci\u00f3n continuar\u00e1 ante el respectivo tribunal o juzgado administrativo. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo.\u00a0El recurso de insistencia deber\u00e1 interponerse por escrito y sustentado en la diligencia de notificaci\u00f3n, o dentro de los diez (10) d\u00edas siguientes a ella\u201d. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>5. Estas disposiciones fueron estudiadas en sede de constitucionalidad por esta Corporaci\u00f3n y declaradas exequibles mediante Sentencia C-951 de 2014, en ejercicio del estudio autom\u00e1tico de normas estatutarias contemplado en los art\u00edculos 153 y 241, numeral 8 de la Constituci\u00f3n. Dijo la Corte:\u00a0 \u00a0<\/p>\n<p>\u201c(\u2026) la Corte encuentra que el establecimiento de un procedimiento sumario para hacer efectivo el derecho de acceso a la informaci\u00f3n, cuando los administrados consideren que este no ha sido satisfecho por parte de la administraci\u00f3n, es id\u00f3neo en la medida en que se trata de un proceso judicial de \u00fanica instancia a trav\u00e9s del cual se decide de manera definitiva sobre la validez de la restricci\u00f3n al acceso de los documentos p\u00fablicos, cuyas caracter\u00edsticas procedimentales en nada ri\u00f1en con el Estatuto Superior y, por el contrario, su estipulaci\u00f3n legal es desarrollo de los art\u00edculos 15, 23, 74 y 209 de la Constituci\u00f3n Pol\u00edtica, pero, adem\u00e1s, se ajusta a los c\u00e1nones del debido proceso previsto en el art\u00edculo 29 Constitucional.\u00a0No obstante lo anterior, a efectos de clarificar el alcance de los t\u00e9rminos previstos para la interposici\u00f3n y tramitaci\u00f3n de este procedimiento, la Corte considera necesario pronunciarse en torno al t\u00e9rmino dentro del cual el funcionario debe remitir la respectiva documentaci\u00f3n al juez o tribunal contencioso administrativo. A la luz de una interpretaci\u00f3n sistem\u00e1tica, los principios de la funci\u00f3n administrativa consagrados en el art\u00edculo 209 de la Constituci\u00f3n en consonancia con el principio de celeridad previsto en el numeral 13 del art\u00edculo 3\u00ba de la Ley 1437 de 2011, norma a la cual se integra el proyecto de ley estatutaria objeto de revisi\u00f3n, considera que la remisi\u00f3n que debe efectuar el funcionario al operador judicial debe ser inmediata. Esto,\u00a0con el fin de salvaguardar de manera efectiva, los derechos fundamentales del peticionario.\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0<\/p>\n<p>De otra parte, habida cuenta que no en todos los 1.104 municipios del pa\u00eds existen juzgados administrativos, para una gran cantidad de personas, el recurso de insistencia ser\u00eda nugatorio y con \u00e9l la posibilidad de oponerse a la negativa de acceso a la informaci\u00f3n y documentos por raz\u00f3n de la reserva invocada por la autoridad. Por tal raz\u00f3n, la Corte considera que en el evento que en el municipio no exista juez administrativo, la competencia para resolver acerca del recurso de insistencia previsto en el art\u00edculo 26 en estudio,\u00a0debe corresponder a cualquier juez del municipio sede de la autoridad que aplic\u00f3 la reserva para negar la petici\u00f3n de informaci\u00f3n o documentos cobijados por la misma. Esto, con el fin de garantizar que todas las personas tengan la oportunidad de interponer el recurso de insistencia contra la negativa a su petici\u00f3n por razones de reserva y de que sea resuelto por una autoridad judicial independiente, acorde con los par\u00e1metros constitucionales y los est\u00e1ndares internacionales que buscan la garant\u00eda efectiva del derecho de petici\u00f3n y el acceso a la informaci\u00f3n y documentos p\u00fablicos. En esa direcci\u00f3n, estima que la exequibilidad de la norma debe ser declarada de manera condicionada, para asegurar la resoluci\u00f3n efectiva y oportuna de este recurso en todos los casos\u201d. \u00a0<\/p>\n<p>6. De este modo, es cierto que antes del 2015 la jurisprudencia constitucional hab\u00eda sostenido que la acci\u00f3n de tutela era el mecanismo judicial id\u00f3neo para solicitar la protecci\u00f3n del derecho fundamental de petici\u00f3n, ante la inexistencia de otro procedimiento ordinario. Sin embargo, hoy en d\u00eda, es claro que con la expedici\u00f3n de la mencionada Ley Estatutaria los ciudadanos cuentan con un proceso destinado exclusivamente a que un funcionario judicial decida, de manera imparcial, si los documentos que una determinada autoridad p\u00fablica ha clasificado como \u201creservados\u201d deben o no ser entregados al solicitante, con lo cual la acci\u00f3n de amparo recobra su car\u00e1cter subsidiario para efectos de proteger el derecho fundamental antedicho.\u00a0 \u00a0<\/p>\n<p>Derecho fundamental al debido proceso administrativo. Reiteraci\u00f3n de jurisprudencia. \u00a0 \u00a0<\/p>\n<p>\u201c\u201ca) \u00a0\u00a0 El derecho a la jurisdicci\u00f3n, que a su vez implica los derechos al libre e igualitario acceso ante los jueces y autoridades administrativas, a obtener decisiones motivadas, a impugnar las decisiones ante autoridades de jerarqu\u00eda superior, y al cumplimiento de lo decidido en el fallo. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>b)\u00a0\u00a0\u00a0\u00a0\u00a0 El derecho al juez natural, identificado este con el funcionario que tiene la capacidad o aptitud legal para ejercer jurisdicci\u00f3n en determinado proceso o actuaci\u00f3n de acuerdo con la naturaleza de los hechos, la calidad de las personas y la divisi\u00f3n del trabajo establecida por la Constituci\u00f3n y la ley. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>c) El derecho a la defensa, entendido como el empleo de todos los medios leg\u00edtimos y adecuados para ser o\u00eddo y obtener una decisi\u00f3n favorable. De este derecho hacen parte, el derecho al tiempo y a los medios adecuados para la preparaci\u00f3n de la defensa; los derechos a la asistencia de un abogado cuando se requiera, a la igualdad ante la ley procesal, el derecho a la buena fe y a la lealtad de todas las dem\u00e1s personas que intervienen en el proceso. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>d) El derecho a un proceso p\u00fablico, desarrollado dentro de un tiempo razonable, lo cual exige que el proceso o la actuaci\u00f3n no se vea sometido a dilaciones injustificadas o inexplicables. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>e)\u00a0El derecho a la independencia del juez, que solo tiene efectivo reconocimiento cuando los servidores p\u00fablicos a los cuales conf\u00eda la Constituci\u00f3n la tarea de administrar justicia, ejercen funciones separadas de aquellas atribuidas al ejecutivo y al legislativo. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>f) El derecho a la independencia e imparcialidad del juez o funcionario, quienes siempre deber\u00e1n decidir con fundamento en los hechos, de acuerdo con los imperativos del orden jur\u00eddico, sin designios anticipados ni prevenciones, presiones o influencias il\u00edcitas.\u201d3 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>8 Esos elementos comportan, a su vez, una serie de prerrogativas concretas en cabeza de los administrados, tales como (i) ser o\u00eddo durante toda la actuaci\u00f3n, (ii)\u00a0ser notificado oportunamente y de conformidad con la ley,\u00a0(iii) el derecho\u00a0a que la actuaci\u00f3n se surta sin dilaciones injustificadas,\u00a0(iv)\u00a0la posibilidad de participar en la actuaci\u00f3n desde su inicio hasta su culminaci\u00f3n,\u00a0(v)\u00a0la obligaci\u00f3n de que la actuaci\u00f3n se adelante por autoridad competente y con el pleno respeto de las formas propias previstas en el ordenamiento jur\u00eddico,\u00a0(vi)\u00a0la garant\u00eda de la presunci\u00f3n de inocencia,\u00a0(vii) el ejercicio del derecho de defensa y contradicci\u00f3n,\u00a0(viii)\u00a0solicitar, aportar y controvertir pruebas, y\u00a0(ix) impugnar las decisiones y a promover la nulidad de aquellas obtenidas con violaci\u00f3n del debido proceso4. \u00a0<\/p>\n<p>9. En consecuencia, puede afirmarse que el derecho al debido proceso administrativo tiene una doble connotaci\u00f3n: por un lado, constituye un l\u00edmite al poder de la administraci\u00f3n en tanto que busca eliminar, en la mayor medida de lo posible, la arbitrariedad y la posibilidad de que los funcionarios afecten otros derechos de los ciudadanos por acci\u00f3n u omisi\u00f3n en el ejercicio de sus funciones. Por otro, implica unas prerrogativas para el ciudadano, de forma que \u00e9ste queda facultado para exigir de manera directa el cumplimiento de un procedimiento previamente establecido por parte de un funcionario competente e imparcial y para discutir, a trav\u00e9s de otros recursos administrativos o de procedimientos judiciales, aquellas decisiones que, a su juicio, no hayan cumplido con los est\u00e1ndares a los que se ha hecho referencia.\u00a0 \u00a0<\/p>\n<p>10. Finalmente, cabe se\u00f1alar que el desarrollo jurisprudencial del derecho fundamental mencionado tambi\u00e9n se ha ocupado de la procedencia de la acci\u00f3n de tutela para la protecci\u00f3n del mismo. As\u00ed, esta Corte ha indicado que, de acuerdo con el principio de subsidiariedad, el amparo constitucional no es el mecanismo judicial id\u00f3neo para resolver las controversias que surgen con ocasi\u00f3n del desarrollo de una actuaci\u00f3n administrativa, en vista de que el legislador ha dispuesto de la jurisdicci\u00f3n contencioso administrativa para tales efectos. Sin embargo, la acci\u00f3n de tutela procede de manera excepcional, ya sea como mecanismo transitorio de protecci\u00f3n en casos en los cuales el accionante logra probar que se encuentra en riesgo de sufrir un perjuicio irremediable o porque se establece que los medios de control ante la jurisdicci\u00f3n de lo contencioso administrativo son ineficaces para la protecci\u00f3n del derecho a la luz de las circunstancias de cada caso en particular, evento en el que opera como mecanismo definitivo. \u00a0<\/p>\n<p>Estudio del caso concreto.\u00a0 \u00a0<\/p>\n<p>11. Con base en las anteriores consideraciones, la Sala pasar\u00e1 a determinar si la acci\u00f3n de tutela impetrada por la se\u00f1ora Irma Casta\u00f1eda contra la Universidad Distrital es procedente. Para esto, se proceder\u00e1 a establecer si la acci\u00f3n cumple los requisitos generales de procedencia y, en caso de que as\u00ed sea, se resolver\u00e1 de fondo.\u00a0 \u00a0<\/p>\n<p>12. Sobre el requisito de legitimaci\u00f3n por activa, se tiene que la acci\u00f3n fue impetrada por la misma persona que considera vulnerados sus derechos, por lo cual se debe entender que este requisito se cumple a cabalidad. Lo mismo puede afirmarse de la legitimaci\u00f3n por pasiva, en vista de que las peticiones que dieron origen a la controversia fueron dirigidas a dicha entidad y contestadas por sus propios funcionarios.\u00a0 \u00a0<\/p>\n<p>13. En cuanto a la inmediatez, se observa que las peticiones y las respuestas radicadas y recibidas por la se\u00f1ora Irma Casta\u00f1eda se produjeron entre los meses de abril y mayo de 2016, mientras que la acci\u00f3n de amparo se interpuso en junio del mismo a\u00f1o. Por ende, no existe duda de que la tutela fue ejercida dentro de un t\u00e9rmino razonable, concomitante a los hechos presuntamente constitutivos de violaci\u00f3n de derechos fundamentales.\u00a0 \u00a0<\/p>\n<p>14. Por su parte, en lo referente a la subsidiariedad, la Sala concuerda con el juez de segunda instancia, en el sentido de que no se tiene evidencia de que la accionante haya hecho uso del recurso de insistencia contenido en el art\u00edculo 26 de la Ley Estatutaria 1755 de 2015 y tampoco existe justificaci\u00f3n de su parte acerca de por qu\u00e9 no acudi\u00f3 a dicho mecanismo. Al respecto, cabe se\u00f1alar que mientras la se\u00f1ora Casta\u00f1eda sosten\u00eda que toda la informaci\u00f3n que hab\u00eda solicitado deb\u00eda ser proporcionada por la Universidad, los funcionarios de la instituci\u00f3n insist\u00edan en que algunos documentos no pod\u00edan ser entregados por estar bajo reserva, de forma que el recurso judicial de insistencia ante la autoridad judicial resultaba id\u00f3neo para resolver definitivamente sobre el tema, en vista de que es un mecanismo dise\u00f1ado precisamente para decidir sobre este tipo de controversias.\u00a0 \u00a0<\/p>\n<p>15. A lo anterior se suma lo informado por la Universidad Distrital en su intervenci\u00f3n del 14 de febrero de 2017, en el sentido de que, luego de ser notificada de la acci\u00f3n de tutela, la instituci\u00f3n educativa procedi\u00f3 a entregar a la accionante todos los documentos faltantes, con excepci\u00f3n de las denuncias y quejas disciplinarias que el Jefe de la Oficina de Asuntos Disciplinarios hab\u00eda interpuesto en su contra, por considerar que son documentos protegidos por la reserva del sumario. Si bien la Sala ya ha establecido que no se pronunciar\u00e1 sobre si estos documentos deben ser o no entregados, vale se\u00f1alar que la accionante puede obtenerlos f\u00e1cilmente constituy\u00e9ndose como parte en los procesos judiciales originados a partir de estos informes o podr\u00e1 solicitarlos nuevamente a la Universidad y, en caso de que se insista en su reserva, podr\u00e1 iniciar el tr\u00e1mite judicial contemplado en la Ley Estatutaria 1755 de 2015.\u00a0 \u00a0<\/p>\n<p>As\u00ed las cosas, al no cumplirse el requisito de subsidiariedad de la acci\u00f3n de tutela, no puede accederse a la solicitud de amparo del derecho fundamental de petici\u00f3n y, en consecuencia, no es posible ordenar a la accionada la entrega inmediata de los documentos solicitados. \u00a0 \u00a0<\/p>\n<p>16. Con todo, para la Sala resulta necesario destacar que s\u00ed se advierte una presunta vulneraci\u00f3n del derecho fundamental al debido proceso administrativo de la se\u00f1ora Irma Casta\u00f1eda, que har\u00eda procedente la acci\u00f3n constitucional, al menos para amparar esa garant\u00eda iusfundamental. Concretamente, la vulneraci\u00f3n habr\u00eda sido producida por el hecho de que varias de las solicitudes elevadas por la accionante a la Universidad fueron resueltas (y negadas, bajo el argumento de la reserva) por el Jefe de la Oficina de Asuntos Disciplinarios que era, al mismo tiempo, denunciante y denunciado en procesos judiciales adelantados en contra y por la se\u00f1ora Casta\u00f1eda, arrojando dudas sobre la imparcialidad del funcionario.\u00a0 \u00a0<\/p>\n<p>17. A pesar de que este asunto no fue alegado en el escrito de tutela, la Sala Novena de Revisi\u00f3n es competente para pronunciarse de fondo al respecto, por dos razones: en primer lugar, no existe una acci\u00f3n judicial ordinaria que permita discutir de manera r\u00e1pida y eficaz la imparcialidad de un funcionario durante el tr\u00e1mite de una solicitud elevada en ejercicio del derecho fundamental de petici\u00f3n. En ese sentido, el recurso contenido en la Ley Estatutaria 1755 de 2015 est\u00e1 dise\u00f1ado para establecer si determinados documentos se encuentran o no bajo reserva, pero no puede ser utilizado para poner en duda la idoneidad del funcionario que conoci\u00f3 del requerimiento. Por otra parte, proponer a la accionante que acuda ante la jurisdicci\u00f3n contencioso \u2013 administrativa s\u00f3lo para establecer la imparcialidad de un funcionario que conoce de una solicitud de informaci\u00f3n constituye, a juicio de la Sala, una exigencia desproporcionada que puede ahondar en la presunta vulneraci\u00f3n de sus derechos.\u00a0 \u00a0<\/p>\n<p>Segundo, la jurisprudencia de esta Corte ha sostenido de manera pac\u00edfica y reiterada que los jueces de tutela tienen la facultad de fallar sobre un asunto distinto al solicitado en caso de que observen, a partir de los hechos, la vulneraci\u00f3n de otros derechos fundamentales. Como lo sostuvo la Sala Plena de esta Corporaci\u00f3n en Sentencia SU \u2013 195 de 2012:\u00a0 \u00a0<\/p>\n<p>\u201cEn cuanto a la posibilidad de que los fallos puedan ser\u00a0extra y ultra petita\u00a0en materia de tutela,\u00a0esta Corte de manera pac\u00edfica ha se\u00f1alado que el juez de tutela puede al momento de resolver el caso concreto conceder el amparo incluso a partir de situaciones o derechos no alegados, atendiendo la informalidad que reviste el amparo y adem\u00e1s quien determina los derechos fundamentales violados. As\u00ed, desde los primeros pronunciamientos se ha sentado esta posici\u00f3n, toda vez que conforme a la condici\u00f3n\u00a0sui generis\u00a0de esta acci\u00f3n, la labor de la autoridad judicial no puede limitarse exclusivamente a las pretensiones invocadas por la parte actora, sino que debe estar encaminada a garantizar el amparo efectivo de los derechos fundamentales. (Subrayado fuera de texto) \u00a0<\/p>\n<p>18. Por lo anterior, la Sala proceder\u00e1 a resolver de fondo sobre la eventual vulneraci\u00f3n del derecho fundamental al debido proceso administrativo de la accionante. Para esto, debe tenerse en cuenta que entre la accionante y el se\u00f1or Ra\u00fal, Jefe de la Oficina de Asuntos Disciplinarios de la Universidad Distrital, existe un conflicto que ha dado origen a varias denuncias disciplinarias y penales. As\u00ed, se tiene que la se\u00f1ora Casta\u00f1eda ha denunciado al se\u00f1or Ra\u00fal por la presunta comisi\u00f3n de actos de abuso de autoridad, maltrato verbal o psicol\u00f3gico, extralimitaci\u00f3n de funciones y acoso laboral o sexual mientras que, a su vez, el se\u00f1or Ra\u00fal ha acusado a la accionante de haber cometido varios delitos contra la administraci\u00f3n p\u00fablica, al punto de haberla denunciado disciplinaria y penalmente ante el Consejo Superior de la Judicatura y la Fiscal\u00eda General de la Naci\u00f3n.\u00a0 \u00a0<\/p>\n<p>19. La importancia de esta circunstancia para el caso que se discute, se encuentra en que los oficios que, en un primer momento, no le fueron entregados a la accionante por parte del Jefe de la Oficina de Asuntos Disciplinarios alegando reserva, son esos a trav\u00e9s de los cuales el mismo se\u00f1or Ra\u00fal solicit\u00f3 ciertos documentos a otras dependencias de la Universidad para poder soportar sus denuncias. En otras palabras, cuando la accionante elev\u00f3 sus solicitudes de informaci\u00f3n, estas fueron conocidas por el mismo funcionario que hab\u00eda promovido denuncias en su contra y contra quien ella hab\u00eda abierto varios procesos, de forma que el se\u00f1or Ra\u00fal actu\u00f3, al mismo tiempo, como Jefe de la Oficina de Asuntos Disciplinarios y como parte interesada cuando decidi\u00f3 negar las copias solicitadas argumentando la existencia de reserva sobre las mismas.\u00a0 \u00a0<\/p>\n<p>20. De este modo, esta Corte encuentra que la accionante no tuvo la oportunidad de que su petici\u00f3n fuese atendida por un funcionario imparcial, con lo cual result\u00f3 vulnerado uno de los componentes del derecho fundamental al debido proceso administrativo a los que se ha hecho referencia en consideraciones anteriores. A juicio de este Tribunal, de haber pretendido la garant\u00eda de todos los derechos de la accionante, el Jefe de la Oficina de Asuntos Disciplinarios debi\u00f3 haberse apartado del conocimiento de las peticiones elevadas por la se\u00f1ora Casta\u00f1eda e informado a las directivas de la Universidad a fin de que nombraran a una persona id\u00f3nea para la soluci\u00f3n de los requerimientos. En el mismos sentido, se observa que otras dependencias universitarias, como por ejemplo la Vicerrector\u00eda Administrativa y las Divisiones de Recursos F\u00edsicos y de Recursos Humanos, ten\u00edan conocimiento del conflicto existente entre la se\u00f1ora Casta\u00f1eda y el se\u00f1or Ra\u00fal y, sin embargo, no advirtieron la necesidad de que los requerimientos elevados por esta \u00faltima fuesen resueltos por un funcionario que no tuviera inter\u00e9s alguno en la resoluci\u00f3n de los mismos. \u00a0<\/p>\n<p>21. As\u00ed, a pesar de que la accionante ya obtuvo la mayor\u00eda de los documentos que solicit\u00f3, la Sala encuentra pertinente ordenar a la Rector\u00eda de la Universidad Distrital Francisco Jos\u00e9 de Caldas que adopte un protocolo de gesti\u00f3n de este tipo de situaciones, de forma que cuando exista duda alguna sobre la imparcialidad del funcionario encargado de resolver una petici\u00f3n, se proceda a nombrar a otro servidor p\u00fablico que no tenga relaci\u00f3n con el caso o con las partes, para que lleve a cabo la contestaci\u00f3n de la misma. La Universidad deber\u00e1 utilizar este procedimiento para atender cualquier solicitud interpuesta por la se\u00f1ora Casta\u00f1eda que deba ser resuelta por la Oficina Asesora de Asuntos Disciplinarios, mientras el Jefe de dicha dependencia sea el se\u00f1or Ra\u00fal.\u00a0 \u00a0<\/p>\n<p>22. Finalmente, dado que se determin\u00f3 que esta Corte no tiene competencia para pronunciarse sobre la entrega de documentos que la Universidad ha se\u00f1alado como reservados (es decir, las denuncias disciplinarias y penales interpuestas por el Jefe de la Oficina de Asuntos Disciplinarios contra la accionante) y con el fin de no afectar la integridad de los procesos judiciales disciplinarios y penales en los que estos se encuentran, se ordenar\u00e1 a la Secretar\u00eda General de esta Corporaci\u00f3n que desglose del expediente y devuelva a la instituci\u00f3n educativa el sobre sellado contentivo de las mencionadas denuncias, remitido a esta Sala mediante oficio fechado el 14 de febrero de 2017. \u00a0 \u00a0<\/p>\n<p>III. DECISI\u00d3N \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Novena de Revisi\u00f3n de la Corte Constitucional, administrando justicia en nombre del pueblo y por mandato de la Constituci\u00f3n,\u00a0 \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>PRIMERO: CONFIRMAR los fallos proferidos por el Juzgado Veinticinco Penal Municipal con Funci\u00f3n de Conocimiento el 12 de julio de 2016, en primera instancia, y por el Juzgado Octavo Penal para Adolescentes con Funci\u00f3n de Conocimiento de Bogot\u00e1 el 27 de julio de 2016, en segunda instancia, dentro de la acci\u00f3n de tutela de referencia, en lo referente al amparo del derecho fundamental de petici\u00f3n.\u00a0 \u00a0<\/p>\n<p>SEGUNDO: AMPARAR el derecho fundamental al debido proceso administrativo de la se\u00f1ora Irma Casta\u00f1eda Ram\u00edrez, por las razones expuestas en la parte motiva de esta providencia.\u00a0 \u00a0<\/p>\n<p>TERCERO: ORDENAR a la Universidad Distrital Francisco Jos\u00e9 de Caldas y, espec\u00edficamente, a la Rector\u00eda de la instituci\u00f3n, que adopte un protocolo de gesti\u00f3n de peticiones, de forma que cuando exista duda alguna sobre la imparcialidad del funcionario encargado de resolver un requerimiento, se proceda a nombrar a otro servidor p\u00fablico que no tenga relaci\u00f3n con el caso o con las partes, para que lleve a cabo la contestaci\u00f3n del mismo. \u00a0<\/p>\n<p>CUARTO: ORDENAR a la Universidad Distrital Francisco Jos\u00e9 de Caldas que, en adelante, todas las peticiones interpuestas por la se\u00f1ora Irma Casta\u00f1eda Ram\u00edrez que deban ser resueltas por la Oficina Asesora de Asuntos Disciplinarios deber\u00e1n ser conocidas por un funcionario ad \u2013 hoc sin relaci\u00f3n de subordinaci\u00f3n con el Jefe de dicha oficina, mientras que el se\u00f1or Ra\u00fal siga teniendo ese cargo.\u00a0 \u00a0<\/p>\n<p>QUINTO: La Secretar\u00eda General de esta Corporaci\u00f3n deber\u00e1 DESGLOSAR del expediente de referencia el sobre sellado que fue radicado en esta Corporaci\u00f3n por parte de la Universidad Distrital junto con el memorial de 14 de Febrero de 2017, seg\u00fan se encuentra en el cuaderno de revisi\u00f3n, por las razones expuestas en las consideraciones de esta sentencia.\u00a0 \u00a0<\/p>\n<p>SEXTO: REMITIR, por intermedio de la Secretar\u00eda General de esta Corporaci\u00f3n, el sobre al que se refiere el numeral anterior a la Universidad Distrital Francisco Jos\u00e9 de Caldas.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>C\u00f3piese, notif\u00edquese, comun\u00edquese, publ\u00edquese en la Gaceta de la Corte Constitucional y c\u00famplase. \u00a0<\/p>\n<p>LUIS ERNESTO VARGAS SILVA \u00a0<\/p>\n<p>Magistrado\u00a0 \u00a0<\/p>\n<p>MAR\u00cdA VICTORIA CALLE CORREA\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Magistrada \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>LUIS GUILLERMO GUERRERO P\u00c9REZ \u00a0 \u00a0\u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0<\/p>\n<p>Secretaria General \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 A petici\u00f3n del apoderado judicial del interesado, quien en escrito radicado el 21 de febrero del 2016, manifest\u00f3 que los derechos fundamentales de su representado pueden verse seriamente comprometidos si quedan sus datos personales en la sentencia emitida por esta Corporaci\u00f3n, en la medida que suponen un prejuzgamiento, pues las razones planteadas en el escrito de insistencia que obra en la p\u00e1gina web de la Corte Constitucional, dejan entrever una situaci\u00f3n f\u00e1ctica que nunca fue dada a conocer por la accionante ante los jueces de instancia. Por tanto la Sala ha decidido reemplazar las referencias a su identificaci\u00f3n en el presente proceso por el seud\u00f3nimo Ra\u00fal. De la misma forma ser\u00e1n reemplazados todos los nombres en el texto de la providencia. \u00a0 \u00a0<\/p>\n<p>2 Sentencia C-980 de 2010.\u00a0 \u00a0<\/p>\n<p>4 Cfr. Sentencias T-051 de 2016, T-957 de 2011 y la ya citada C-980 de 2010, entre otras.\u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia T-119\/17 \u00a0 LEY ESTATUTARIA DEL DERECHO DE PETICION-Regulaci\u00f3n de la informaci\u00f3n sometida a reserva\u00a0 \u00a0 Es cierto que antes del 2015 la jurisprudencia constitucional hab\u00eda sostenido que la acci\u00f3n de tutela era el mecanismo judicial id\u00f3neo para solicitar la protecci\u00f3n del derecho fundamental de petici\u00f3n, ante la inexistencia de otro procedimiento ordinario. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[118],"tags":[],"class_list":["post-25307","post","type-post","status-publish","format-standard","hentry","category-tutelas-2017"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/25307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=25307"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/25307\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=25307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=25307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=25307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}