{"id":2582,"date":"2024-05-30T17:00:56","date_gmt":"2024-05-30T17:00:56","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/05\/30\/t-406-96\/"},"modified":"2024-05-30T17:00:56","modified_gmt":"2024-05-30T17:00:56","slug":"t-406-96","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-406-96\/","title":{"rendered":"T 406 96"},"content":{"rendered":"<p>T-406-96<\/p>\n<p>&nbsp; &nbsp; Expediente T-96.084 &nbsp;<\/p>\n<p>Sentencia T-406\/96 &nbsp;<\/p>\n<p>CONTRATO DE TRABAJO DE PERSONAL DOCENTE-Solicitud vinculaci\u00f3n departamental &nbsp;<\/p>\n<p>Trat\u00e1ndose de dos grupos de docentes vinculados de manera distinta, no obstante cumplir la misma labor, es s\u00f3lo entre los educadores de la Gobernaci\u00f3n, en quienes cabe la aplicaci\u00f3n del derecho fundamental a la igualdad, m\u00e1s no entre \u00e9stos y los que laboran al servicio de la entidad privada, raz\u00f3n por la cual no es posible invocar la vulneraci\u00f3n de este derecho fundamental, cuando las partes con las cuales est\u00e1n vinculados los docentes oficiales, y los ligados por contrato de trabajo con la entidad privada, son distintas. &nbsp;<\/p>\n<p>MEDIO DE DEFENSA JUDICIAL-Litigios contractuales &nbsp;<\/p>\n<p>La acci\u00f3n de tutela no es procedente para dirimir situaciones litigiosas con ocasi\u00f3n de la aplicaci\u00f3n de los respectivos contratos, para los efectos del cumplimiento de las obligaciones inherentes a los mismos, ya que dicha definici\u00f3n de la respectiva controversia corresponde a la justicia laboral, con respecto a las diferencias surgidas de la interpretaci\u00f3n del contrato de trabajo. Debe advertirse que la relaci\u00f3n existente entre el Departamento y la Fundaci\u00f3n no es de car\u00e1cter laboral, sino de naturaleza administrativa que puede derivar obligaciones de la misma \u00edndole con el Departamento. &nbsp;<\/p>\n<p>Referencia: Expedientes T-94490 y T- &nbsp;<\/p>\n<p>96737&nbsp; &nbsp;<\/p>\n<p>Peticionarias: Adriana Posso Vidal y Elsa Elena Andrade S\u00e1nchez en contra de la Gobernaci\u00f3n del Valle del cauca- Secretar\u00eda de Educaci\u00f3n Departamental. &nbsp;<\/p>\n<p>Procedencia: Tribunal Superior del Distrito Judicial de Cali- Sala Civil. &nbsp;<\/p>\n<p>Magistrado Ponente: &nbsp;<\/p>\n<p>Dr. HERNANDO HERRERA VERGARA &nbsp;<\/p>\n<p>Santa Fe de Bogot\u00e1, D.C., veintitr\u00e9s (23) de agosto de mil novecientos noventa y seis (1996). &nbsp;<\/p>\n<p>Los expedientes llegaron al conocimiento de esta Sala de Revisi\u00f3n de la Corte Constitucional por remisi\u00f3n que hiciera el Tribunal Superior del Distrito Judicial de Cali, de acuerdo con lo dispuesto en el art\u00edculo 31 del Decreto 2591 de 1991. &nbsp;<\/p>\n<p>Con fundamento en los art\u00edculos 86 de la Constituci\u00f3n Pol\u00edtica, y 33 del Decreto 2591 de 1991, la Sala de Selecci\u00f3n &nbsp;N\u00famero Cinco (5) de la Corte Constitucional, mediante auto del veintid\u00f3s (22) de mayo de 1996, los escogi\u00f3 y acumul\u00f3 para efectos de revisi\u00f3n, las acciones de tutela, en el proceso de la referencia. &nbsp;<\/p>\n<p>I. ANTECEDENTES &nbsp;<\/p>\n<p>Las Ciudadanas Adriana Posso Vidal y Elsa Elena Andrade S\u00e1nchez, en escritos separados, promovieron acci\u00f3n de tutela en contra de la Gobernaci\u00f3n del Valle del Cauca, Secretar\u00eda de Educaci\u00f3n, para que se les protegieran los derechos fundamentales de petici\u00f3n e igualdad. &nbsp;<\/p>\n<p>En relaci\u00f3n con el derecho de petici\u00f3n, aducen que la Secretar\u00eda de Educaci\u00f3n Departamental no les ha contestado el escrito que le elevaron el 13 de diciembre de 1995, por medio del cual solicitaron que se les nombrara oficialmente como profesores del Departamento, para continuar el programa de educaci\u00f3n adelantado por la Gobernaci\u00f3n del Departamento del Valle del Cauca, denominado &#8220;PREZOMA&#8221;. Y con respecto al derecho a la igualdad, por cuanto, no obstante el fallo de la Corte Constitucional que declar\u00f3 inexequible el par\u00e1grafo 3 del art\u00edculo 105 de la Ley 115 de 1994, y el par\u00e1grafo 1\u00b0 del art\u00edculo 6\u00b0 de la Ley 60 de 1993 que prohibi\u00f3 la &#8220;vinculaci\u00f3n de educadores por contrato a las entidades territoriales, el Departamento del Valle del Cauca, ha pretendido evitar el compromiso que implica la vinculaci\u00f3n de los maestros por la v\u00eda legal y reglamentaria&#8221;, toda vez que ha &#8220;&#8216;disfrazado&#8217; este compromiso realizando un contrato de prestaci\u00f3n de servicios con una entidad privada que usufruct\u00faa para este fin recursos exclusivamente provenientes del Estado, y generando, sin embargo, una odiosa discriminaci\u00f3n para todos los maestros contratados&#8221; por la Fundaci\u00f3n Prodesarrollo de la Educaci\u00f3n Preescolar del Valle FUNDAPRE&#8221;. &nbsp;<\/p>\n<p>Por consiguiente, solicitan que se ordene al Departamento del Valle del Cauca, Secretar\u00eda de Educaci\u00f3n, a vincularlas como educadoras al servicio de \u00e9ste, mediante &#8220;nombramiento legalmente realizado&#8221;, puesto que, a su juicio, re\u00fanen los requisitos para tales efectos, y por cuanto &#8220;es el Departamento la entidad que realmente asume la prestaci\u00f3n del servicio de educaci\u00f3n inicial obligatoria (Grado Cero) y no FUNDAPRE&#8221;. Permitir esto, aducen, es violar el art\u00edculo 13 de la Carta Pol\u00edtica en la medida en que se las discrimina frente a otros trabajadores. &nbsp;<\/p>\n<p>Manifiestan que celebraron un contrato de trabajo con &#8220;FUNDAPRE&#8221;, como maestra de preescolar, para que esta Fundaci\u00f3n ejecutara un contrato de prestaci\u00f3n de servicios con la Secretar\u00eda de Educaci\u00f3n Departamental. Que dicha Secretar\u00eda pretende cumplir la obligaci\u00f3n derivada de lo preceptuado en el art\u00edculo 17 de la Ley 115 de 1994 o Ley General de Educaci\u00f3n, que reza &#8220;El nivel de educaci\u00f3n preescolar comprende como m\u00ednimo, un grado obligatorio en los establecimientos educativos estatales para ni\u00f1os menores de seis a\u00f1os de edad&#8230;&#8221;. Indican que desde 1992 se dise\u00f1\u00f3 el plan para tal efecto, el cual preve\u00eda que los recursos provendr\u00edan del &#8220;Ministerio de Educaci\u00f3n Nacional, mediante transferencias que se le har\u00edan a las alcald\u00edas de los municipios con destino a la dotaci\u00f3n de mobiliario material did\u00e1ctico para las escuelas donde funcione el Grado Cero y tambi\u00e9n para la capacitaci\u00f3n de docentes por intermedio del Centro Experimental Piloto. Refieren, que el \u201cplan se\u00f1alaba tambi\u00e9n que el Gobierno Departamental gestionar\u00eda y apoyar\u00eda la consecuci\u00f3n de recursos para la vinculaci\u00f3n de los docentes, y asumir\u00eda la responsabilidad para efectuar el seguimiento y asesor\u00eda durante el proyecto&#8221;. &nbsp;<\/p>\n<p>Agregan que todos los maestros que como ellas iniciaron la prestaci\u00f3n del servicio con la Fundaci\u00f3n, siguen siendo contratados a t\u00e9rmino definido y cobijados por el r\u00e9gimen del C\u00f3digo Sustantivo del Trabajo, a pesar que el servicio es financiado por el Estado y prestado en locales que son de propiedad &nbsp;de \u00e9ste. &nbsp;<\/p>\n<p>Finalmente, refieren que no se les paga oportunamente los salarios; pero que cuando se los cancelan, esto ocurre sin la observancia de lo dispuesto por la Corte Constitucional que obliga al pago del 100% del valor de las categor\u00edas oficiales del escalaf\u00f3n docente, lo que est\u00e1 ocasionando incertidumbre para la vinculaci\u00f3n de cualquier educador para el a\u00f1o lectivo siguiente, pues, solo han recibido el salario del mes de enero de 1996, faltando algunos meses por pagar del a\u00f1o inmediatamente anterior. Por tanto, solicitan, que &#8220;se investigue la naturaleza de la relaci\u00f3n contractual entre la Gobernaci\u00f3n del Valle y la fundaci\u00f3n FUNDAPRE&#8221;, y adem\u00e1s, les paguen &#8220;los salarios dejados de percibir como consecuencia de la inaplicaci\u00f3n de los fallos de la Corte Constitucional&#8221;. &nbsp;<\/p>\n<p>II. LAS DECISIONES JUDICIALES QUE SE REVISAN &nbsp;<\/p>\n<p>Expediente No. T- 94490 &nbsp;<\/p>\n<p>a) &nbsp;Sentencia proferida en primera instancia por el Juzgado Cuarto Civil del Circuito de Santiago de Cali.&nbsp; &nbsp;<\/p>\n<p>Correspondi\u00f3 conocer la acci\u00f3n de tutela al Juzgado Cuarto Civil del Circuito de Santiago de Cali, el cual mediante sentencia del veinte (20) de febrero de 1996, &nbsp;neg\u00f3 la tutela instaurada por Adriana Posso Vidal, con fundamento en las siguientes razones: &nbsp;<\/p>\n<p>En relaci\u00f3n con el derecho de petici\u00f3n, considera el Despacho que no se conculc\u00f3, puesto que el Gobernador del Valle del Cauca, s\u00ed respondi\u00f3 la solicitud, mediante oficio de enero 23 de 1996, como consta a folios 28, 29 y 30. &nbsp;<\/p>\n<p>Respecto al derecho a la igualdad estim\u00f3 que no existe vulneraci\u00f3n, toda vez que, &#8220;no es igual la condici\u00f3n laboral del trabajador o del educador de una entidad privada, que la del trabajador o educador del sector oficial, en consecuencia, ante situaciones desiguales no puede pregonarse trato igual&#8221;. En el presente caso, la demandante se vincul\u00f3 a la Fundaci\u00f3n Prodesarrollo de la Educaci\u00f3n Pre-escolar del Valle (FUNDAPRE), por medio de un contrato de trabajo a t\u00e9rmino fijo, y que siendo la fundaci\u00f3n una entidad privada, no puede aspirar a que se le d\u00e9 un mismo tratamiento que el empleado o trabajador oficial por el hecho de tener la Fundaci\u00f3n un contrato de prestaci\u00f3n de servicios con la Secretar\u00eda de Educaci\u00f3n del Departamento del Valle del Cauca, y cumplir, a trav\u00e9s del mismo, obligaciones legales impuestas a \u00e9sta. &nbsp;<\/p>\n<p>Acerca de las controversias originadas con los salarios dejados de percibir, considera ese despacho que no le corresponde dirimirlos al juez de tutela, ya que para ello existen las correspondientes acciones legales, ante la jurisdicci\u00f3n laboral o ante la Contencioso Administrativa, si lo que se ataca es el contrato de prestaci\u00f3n de servicios con la gobernaci\u00f3n. &nbsp;<\/p>\n<p>Impugnaci\u00f3n. &nbsp;<\/p>\n<p>La peticionaria impugn\u00f3 el fallo proferido por el Juzgado Cuarto Civil del Circuito de Santiago de Cali, la cual correspondi\u00f3 resolver al Tribunal Superior del Distrito Judicial de esta misma ciudad, Sala Civil. &nbsp;<\/p>\n<p>b) &nbsp;Sentencia proferida por el Tribunal Superior del Distrito Judicial de Cali, Sala Civil. &nbsp;<\/p>\n<p>Correspondi\u00f3 conocer en segunda instancia la acci\u00f3n de tutela presentada por Adriana Posso Vidal, al Tribunal Superior del Distrito Judicial de Cali, Sala Civil, el cual, mediante sentencia del seis (6) de marzo de 1996, resolvi\u00f3 confirmar la tutela, con fundamento en las siguientes razones: &nbsp;<\/p>\n<p>Respecto del derecho de petici\u00f3n, no existe violaci\u00f3n del mismo por cuanto qued\u00f3 demostrado, seg\u00fan lo expresado por el Secretario de Educaci\u00f3n Departamental, que la petici\u00f3n s\u00ed fue contestada en debida forma, como consta en el expediente a folio 25. &nbsp;<\/p>\n<p>De igual forma, considera que no existe vulneraci\u00f3n del derecho de igualdad, ya que la actora no se encuentra en la misma situaci\u00f3n laboral que los docentes oficiales, pues, \u00e9sta suscribi\u00f3 un contrato individual de trabajo con una entidad privada denominada &#8220;FUNDAPRE&#8221;, mientras que los otros docentes tienen un contrato de trabajo distinto, raz\u00f3n por la cual a dos situaciones de hecho diferentes no se le puede dar una trato igualitario. &nbsp;<\/p>\n<p>Expediente n\u00famero T-96737 &nbsp;<\/p>\n<p>a) &nbsp;Sentencia proferida, en primera instancia por el Juzgado Sexto Civil del Circuito de &nbsp; Cali. &nbsp;<\/p>\n<p>Correspondi\u00f3 conocer en primera instancia la acci\u00f3n de tutela presentada por Elsa Elena Andrade S\u00e1nchez, al Juzgado Sexto Civil del Circuito de Cali, el cual, mediante sentencia de veintiseis (26) de febrero de 1996, resolvi\u00f3 denegar la tutela, con fundamento en las siguientes razones: &nbsp;<\/p>\n<p>El derecho de petici\u00f3n de la solicitante, de acuerdo con lo expresado por el Secretario de Educaci\u00f3n Departamental, fue contestado por el se\u00f1or Gobernador del Departamento del Valle, mediante oficio de fecha 23 de enero de 1996 y enviado por fax el d\u00eda 7 de febrero del presente a\u00f1o a la se\u00f1ora Tulia de Quintero, Directora de PREZOMA, en donde se le reitera que la forma de vinculaci\u00f3n de la actora se entiende como privada y no oficial, raz\u00f3n por la cual no le corresponde al Departamento del Valle, responder por lo salarios adeudados. Del mismo modo, en dicho oficio se le inform\u00f3 que para poder ingresar como educadores al sector oficial, debe llenarse los requisitos establecidos en la Ley 115 de 1994, art\u00edculo 105, de la ley General de Educaci\u00f3n. &nbsp;<\/p>\n<p>Con respecto al derecho de igualdad, manifiesta &#8220;que no se ha probado la discriminaci\u00f3n de que habla la peticionaria, ya que para efectos de la vinculaci\u00f3n como educadora al servicio del Departamento debe llenar los requisitos del art\u00edculo 105, Ley 115 de 1994, teniendo en cuenta la vinculaci\u00f3n de car\u00e1cter privado que existe entre la fundaci\u00f3n PREZOMA y el Departamento del Valle del Cauca. &nbsp;<\/p>\n<p>Impugnaci\u00f3n. &nbsp;<\/p>\n<p>La peticionaria impugn\u00f3 el fallo proferido por el Juzgado Sexto Civil del Circuito de Santiago de Cali, la cual correspondi\u00f3 resolver al Tribunal Superior del Distrito Judicial de esta misma ciudad, Sala Civil. &nbsp;<\/p>\n<p>b) &nbsp;Sentencia proferida por el Tribunal Superior del Distrito Judicial de Cali, Sala Civil. &nbsp;<\/p>\n<p>El Tribunal Superior del Distrito Judicial de Cali, Sala Civil, mediante providencia de fecha veintisiete (27) de marzo de 1996, resolvi\u00f3 confirmar la sentencia proferida por el Juzgado Sexto Civil del Circuito de la misma ciudad, y previno al Gobernador del Departamento del Valle del Cauca, con base en el art\u00edculo 24 del Decreto 2591 de 1991, &#8220;para que en adelante se abstenga de incurrir en conductas de retardo (&#8230;)&#8221; como la ocurrida en el caso en estudio, con base en las siguientes consideraciones: &nbsp;<\/p>\n<p>Respecto a la vulneraci\u00f3n del derecho de petici\u00f3n, considera el Tribunal que no existe violaci\u00f3n, ya que la solicitud presentada fue contestada en forma oportuna por medio del oficio de 23 de enero de 1996 y enviada por fax el d\u00eda 7 de febrero de 1996, en el cual se pone de presente que no existe vinculaci\u00f3n laboral alguna entre la Gobernaci\u00f3n y la actora, afirmando igualmente que la relaci\u00f3n entre los docentes y la fundaci\u00f3n no es &#8220;oficial sino privada&#8221;. Empero previno a la accionada por el retardo en la respuesta. &nbsp;<\/p>\n<p>En cuanto al derecho a la igualdad, considera que debido a que la peticionaria se encuentra vinculada con &#8220;FUNDAPRE&#8221;, mediante contrato individual de trabajo para hacer las veces de docente, y que &#8220;en el texto de ninguno de los contratos aportados figura el Departamento del valle del Cauca como parte obligada, ni esta entidad oficial asume all\u00ed obligaciones laborales o prestacionales para con la trabajadora o docente Andrade S\u00e1nchez&#8221;, no se vislumbra trato discriminatorio, ya que por mandato de la Ley General de Educaci\u00f3n &#8220;debe mediar el cumplimiento de perentorios requisitos&#8221; seg\u00fan lo dispone el inciso 2\u00b0 del art\u00edculo 105 de la citada Ley 115 de 1994. &nbsp;<\/p>\n<p>III. CONSIDERACIONES DE LA CORTE CONSTITUCIONAL. &nbsp;<\/p>\n<p>1. &nbsp;La Competencia. &nbsp;<\/p>\n<p>De conformidad con lo dispuesto en los art\u00edculos 86 inciso tercero y 241 numeral noveno de la Constituci\u00f3n Pol\u00edtica, en concordancia con los art\u00edculos 33 a 36 del Decreto 2591 de 1991, esta Sala es competente para revisar los fallos proferidos por el Juzgado Cuarto Civil del Circuito de Santiago de Cali y &nbsp;Sexto Civil del Circuito de esta misma ciudad, y por el Tribunal Superior del Distrito Judicial de Cali, Sala Civil. &nbsp;<\/p>\n<p>2. &nbsp;El derecho fundamental de petici\u00f3n en el caso objeto de estudio. &nbsp;<\/p>\n<p>Ha reiterado esta Corte, por medio de la jurisprudencia constitucional a trav\u00e9s de sus distintas Salas de Revisi\u00f3n de tutela, que la pronta resoluci\u00f3n de las peticiones respetuosas presentadas ante las autoridades por motivos de inter\u00e9s general o particular, constituye el n\u00facleo esencial de este derecho fundamental, pues, &#8220;sin la posibilidad de exigir una respuesta r\u00e1pida y oportuna carecer\u00eda de efectividad este derecho1&#8221; y que, adem\u00e1s, &#8220;ser\u00eda inocuo si solo se formulara en t\u00e9rminos de poder presentar la respectiva petici\u00f3n2&#8221;. De igual modo, cabe destacar que la efectividad de este derecho fundamental est\u00e1 sujeta a que la petici\u00f3n sea resuelta de manera r\u00e1pida, cuya respuesta debe ser coherente y aludir al fondo de lo que se solicita, por cuanto &#8220;es en la resoluci\u00f3n y no en la formulaci\u00f3n donde (&#8230;) adquiere toda su dimensi\u00f3n como instrumento eficaz de la participaci\u00f3n democr\u00e1tica3&#8221;. &nbsp;Al respecto consider\u00f3 esta Corporaci\u00f3n: &nbsp;<\/p>\n<p>&#8220;Considera la Corte que el derecho de petici\u00f3n no tendr\u00eda sentido si se entendiera que la autoridad ante quien se presenta una solicitud respetuosa cumple su obligaci\u00f3n notificando o comunicando una respuesta apenas formal en la que no se resuelva sobre el asunto planteado. El derecho de petici\u00f3n lleva impl\u00edcito un concepto de decisi\u00f3n material, real y verdadero, no apenas aparente. Por tanto, se viola cuando, a pesar de la oportunidad de la respuesta, en \u00e9sta se alude a temas diferentes de los planteados o se evade la determinaci\u00f3n que el funcionario deba adoptar4&#8221;. &nbsp;<\/p>\n<p>Ahora bien, no se conculca este principio esencial cuando se le responde al peticionario la solicitud de manera negativa, puesto que ella, en la medida en que se refiera al fondo del asunto, debidamente fundamentado, y &#8220;siempre y cuando se produzca dentro de los t\u00e9rminos que la ley se\u00f1ala, representa en s\u00ed misma, independientemente de su sentido, la satisfacci\u00f3n del derecho de petici\u00f3n5&#8221;.&nbsp; &nbsp;<\/p>\n<p>As\u00ed mismo, debe resaltarse que para alcanzar la efectividad del n\u00facleo esencial del mencionado principio, esto es, la &#8220;pronta resoluci\u00f3n&#8221;, debe el interesado cumplir, por lo menos, con el lleno de los requisitos relacionados en el art\u00edculo 5\u00b0 del C\u00f3digo Contencioso Administrativo, es decir, la designaci\u00f3n de la autoridad a la que se dirige; &#8220;los nombres y apellidos completos del solicitante y de su representante o apoderado, si es el caso, con indicaci\u00f3n del documento de identidad y de la direcci\u00f3n&#8221;; el objeto de la petici\u00f3n; las razones en que se apoya; la relaci\u00f3n de documentos que se acompa\u00f1an; y la firma del peticionario. &nbsp;<\/p>\n<p>Respecto del t\u00e9rmino que dispone la administraci\u00f3n para resolver las peticiones, como lo ha sostenido la Corte6, se deben tener en cuenta las disposiciones del C\u00f3digo Contencioso Administrativo y, en lo pertinente, la ley 57 de 1994. Todo lo anterior tiene sustento en que si &#8220;despu\u00e9s de la promulgaci\u00f3n de la nueva Constituci\u00f3n, no se ha dictado normatividad alguna que desarrolle y regule aspectos esenciales del derecho de petici\u00f3n, s\u00ed existe una regulaci\u00f3n que fue expedida con anterioridad a su vigencia y que a\u00fan rige la materia, pues la expedici\u00f3n de la nueva Carta, no derog\u00f3 la legislaci\u00f3n existente&#8221;. &nbsp;<\/p>\n<p>En este orden de ideas, el art\u00edculo 6\u00b0 del C\u00f3digo Contencioso Administrativo, expresa que el t\u00e9rmino para resolver las peticiones de car\u00e1cter general o particular es de quince (15) d\u00edas a la fecha de su recibo, en cuyo lapso, de igual forma, podr\u00e1 la administraci\u00f3n informar al peticionario que le es imposible resolver o contestar la petici\u00f3n, pero, &#8220;expresando los motivos de la demora y se\u00f1alando a la vez la fecha en que se resolver\u00e1 o dar\u00e1 respuesta7&#8221; a la misma.&nbsp; &nbsp;<\/p>\n<p>As\u00ed, entonces, una vez enterado al peticionario acerca de los motivos de la demora y de la fecha en que se dar\u00e1 resoluci\u00f3n o respuesta a la petici\u00f3n, &#8220;dicho t\u00e9rmino debe ajustarse a los par\u00e1metros de la razonabilidad, razonabilidad que debe consultar no s\u00f3lo la importancia que el asunto pueda revestir &nbsp;para el solicitante, sino los distintos tr\u00e1mites que debe agotar la administraci\u00f3n para resolver adecuadamente la cuesti\u00f3n planteada. Por tanto, ante la ausencia de una norma que se\u00f1ale dicho t\u00e9rmino, el juez de tutela, en cada caso, tendr\u00e1 que determinar si el plazo que la administraci\u00f3n fij\u00f3 y emple\u00f3 para contestar la solicitud, fue razonable, y si se satisfizo el n\u00facleo esencial del derecho de petici\u00f3n: la pronta resoluci\u00f3n8&#8221;.&nbsp; &nbsp;<\/p>\n<p>En el caso subjudice, las demandantes solicitaron inicialmente la protecci\u00f3n del derecho fundamental de petici\u00f3n, al Gobernador del Departamento del Valle del Cauca que las nombrara oficialmente como profesoras del Departamento, para continuar el programa de educaci\u00f3n adelantado por la Gobernaci\u00f3n del Departamento del Valle del Cauca, denominado &#8220;PREZOMA&#8221;, sin que, a juicio de \u00e9stas, aqu\u00e9l les haya dado respuesta. &nbsp;<\/p>\n<p>El Tribunal Superior de Cali, al conocer en segunda instancia de las acciones de tutela, confirm\u00f3 los fallos proferidos por los Juzgados Cuarto Civil del Circuito de Cali y Sexto Civil del Circuito de esta misma ciudad, los cuales a su vez las denegaron, con fundamento en que la petici\u00f3n fue resuelta por el demandado, el 23 del enero de 1996, en el sentido de indicarles que &#8220;El Departamento del Valle del Cauca celebr\u00f3 el 3 de marzo de 1995 un contrato de prestaci\u00f3n de servicios con la Fundaci\u00f3n Pro-Desarrollo de la Educaci\u00f3n Pre- escolar del Valle- (&#8230;), con el fin de prestar el servicio educativo pre-escolar a un m\u00ednimo de 2.500 ni\u00f1os de escasos recursos econ\u00f3micos matriculados en el Grado Cero&#8221;; que, por consiguiente, no es \u00e9ste, sino FUNDAPRE, la entidad que debe asumir los costos de los honorarios o salarios a que haya lugar. De igual modo, les inform\u00f3 que no exist\u00eda v\u00ednculo laboral entre el Departamento y la Fundaci\u00f3n, seg\u00fan lo establec\u00eda el art\u00edculo 32, numeral 3 inciso 2 de la ley 80 de 1993 y que para ingresar como educadores del sector oficial, deb\u00edan llenar los requisitos establecidos en el art\u00edculo 105 de la Ley 115 de 1994. &nbsp;<\/p>\n<p>Cabe aclarar que, en relaci\u00f3n con la tutela cuya accionante es Elsa Elena Andrade S\u00e1nchez, el Tribunal previno al Gobernador del Departamento del Valle del Cauca, con base en el art\u00edculo 24 del Decreto 2591 de 1991, para que en adelante se abstuviera de incurrir en conductas de retardo, como la ocurrida en el caso objeto de estudio. &nbsp;<\/p>\n<p>Esta Sala comparte parcialmente las consideraciones que llevaron al Tribunal Superior de Cali a confirmar los fallos de las respectivas instancias en relaci\u00f3n con el derecho fundamental de petici\u00f3n, por cuanto, despu\u00e9s de revisar el material probatorio que obra en los expedientes, y lo referente a la formalidad de la petici\u00f3n, encontr\u00f3 que las actoras, omitieron el se\u00f1alamiento de la direcci\u00f3n del remitente o destinatario, la cual era necesaria para que el accionado enterara a las accionantes de manera oportuna, durante el t\u00e9rmino aludido en el art\u00edculo 5\u00b0 del C.C.A, del contenido de la misma. No obstante, como lo firma el Secretario de Educaci\u00f3n del Departamento de Cali, el Gobernador hab\u00eda resuelto la solicitud y la envi\u00f3 mediante fax, por conducto de la Directora de la Fundaci\u00f3n Prodesarrollo de la Educaci\u00f3n Preescolar del Valle (PREZOMA), el 7 de febrero de 1996, dando resoluci\u00f3n a lo solicitado por ellas.&nbsp; &nbsp;<\/p>\n<p>Sobre el punto mencionado ha expresado esta Sala: &nbsp;<\/p>\n<p>En el caso sub-examine se observa que el interesado en la petici\u00f3n no cumpli\u00f3 estos requisitos y no se le pudo enterar de la respuesta exigida. En efecto, el interesado no se\u00f1al\u00f3 la direcci\u00f3n donde pod\u00eda notificarse o comunicarse la respuesta correspondiente o donde pod\u00eda inform\u00e1rsele &#8220;la determinaci\u00f3n adoptada (aceptaci\u00f3n o rechazo) o los motivos de demora para su resoluci\u00f3n e indicaci\u00f3n de la fecha en que se le dar\u00e1 respuesta&#8221;. &nbsp;<\/p>\n<p>&#8220;Lo cierto es que, como se advirti\u00f3, no es posible en todos los casos atender el derecho de petici\u00f3n si el interesado no cumple con los requisitos se\u00f1alados por la Ley para hacerlo viable y efectivo, entre ellos el de se\u00f1alar su direcci\u00f3n. (&#8230;) Si el particular desea el respeto a su derecho ha de suministrar a la autoridad todos los datos e informaciones que permitan su cabal e \u00edntegra satisfacci\u00f3n; esa conjunci\u00f3n entre particular y autoridad resulta indispensable al objetivo de lograr la plena efectividad de los derechos contemplados en la Carta. &nbsp;<\/p>\n<p>Pese a lo anterior, no escapa a la Sala que la protecci\u00f3n de los derechos constitucionales fundamentales requiere de la administraci\u00f3n un comportamiento diligente, si bien es cierto una deficiencia de la petici\u00f3n inicial, como la anotada, imposibilita el enteramiento de lo decidido, esa sola circunstancia no exime de analizar el asunto planteado y de obrar dentro de los t\u00e9rminos legales para arribar a una decisi\u00f3n pronta, las dificultades que se presenten para comunicar al peticionario lo resuelto son posteriores y suponen que la soluci\u00f3n ya fue tomada, salvo que no es posible enterar al administrado, por ignorarse su direcci\u00f3n9&#8243;. &nbsp;<\/p>\n<p>As\u00ed las cosas, aunque la notificaci\u00f3n de la respuesta de la petici\u00f3n fue tard\u00eda no comparte la Sala el criterio del Tribunal, al heber dispuesto la prevenci\u00f3n de retardo al Gobernador del Departamento, teniendo en cuenta la omisi\u00f3n en suministrar la direcci\u00f3n de las accionantes, lo que impidi\u00f3 la respuesta oportuna. Sin embargo, dicha prevenci\u00f3n se satifizo con el efecto inmediato que produjo la providencia dictada por el mencionado Tribunal, aunque no era procedente por los motivos expresados. &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>3. An\u00e1lisis del derecho fundamental a la igualdad, en el caso subexamine. &nbsp;<\/p>\n<p>Ahora bien, en relaci\u00f3n con el caso objeto sub-examine y respecto del derecho fundamental que se analiza, del texto de la demanda de tutela se desprende la pretensi\u00f3n principal de las accionantes seg\u00fan la cual se debe ordenar a la Gobernaci\u00f3n del Departamento del Valle del Cauca a que las vincule como educadoras al servicio de \u00e9ste, &#8220;mediante nombramiento legalmente realizado, dado que, a su juicio, re\u00fanen los requisitos para tal fin. Sin embargo, es pertinente anotar que las demandantes, seg\u00fan se desprende de los hechos consignados en las respectivas demandas, y de las pruebas que se hallan en los expedientes, est\u00e1n vinculadas a la Fundaci\u00f3n Prodesarrollo de la Educaci\u00f3n Pre-escolar del Valle, FUNDAPRE, mediante contrato de trabajo, y no a la Gobernaci\u00f3n del Departamento del Valle del Cauca, con la cual la FUNDAPRE suscribi\u00f3 contrato de prestaci\u00f3n de servicios. &nbsp;<\/p>\n<p>En efecto, el Gobernador del &nbsp;citado Departamento, al contestar la petici\u00f3n elevada por las accionantes, mediante el oficio de fecha 23 de enero de 1996, les indic\u00f3 que exist\u00eda un contrato de prestaci\u00f3n de servicio entre el Departamento y FUNDAPRE, celebrado el 3 de diciembre de 1995, como as\u00ed lo afirma el Secretario de Educaci\u00f3n, en el cual pactaron lo siguiente: &nbsp;<\/p>\n<p>&#8220;(&#8230;) Cl\u00e1usula Segunda: OBLIGACIONES DEL CONTRATISTA, que para efectos del mismo es la Fundaci\u00f3n, quien se compromete a vincular al programa 84 docentes relacionados en la lista elaborada por FUNDAPRE- Fundaci\u00f3n Pro-desarrollo de la Educaci\u00f3n, documento que hace parte integral del Contrato y, a asumir los costos de honorarios o salarios a que haya lugar. En su Cl\u00e1usula S\u00e9ptima: INEXISTENCIA DE RELACION LABORAL., establece que por tratarse de un Contrato de Prestaci\u00f3n de Servicios, las partes, en este caso el Departamento y la Fundaci\u00f3n, entienden y acuerdan expresamente que entre ellos no existe vinculaci\u00f3n laboral alguna, seg\u00fan lo se\u00f1alado en el art\u00edculo 32, numeral 3, inciso 2 de la Ley 80 de 1993. &nbsp;<\/p>\n<p>Tambi\u00e9n les inform\u00f3: &#8220;Cualquiera que sea la forma de vinculaci\u00f3n de ustedes con la Fundaci\u00f3n, se entiende como privada, no como oficial, por lo tanto, no es el Departamento del Valle del Cauca, en t\u00e9rminos laborales, el responsable de sus salarios&#8221;; que si quer\u00edan ingresar como educadoras del sector oficial, deb\u00edan llenar los requisitos establecidos en el art\u00edculo 105, de la Ley 115 de 1994, Ley General de la Educaci\u00f3n.&nbsp; &nbsp;<\/p>\n<p>&nbsp;El Tribunal Superior de Cali confirm\u00f3 los fallos de los Juzgados de primera instancia que denegaron la tutela, en relaci\u00f3n con este derecho, en raz\u00f3n a que no era igual la situaci\u00f3n laboral del educador de una entidad privada con respecto al del sector oficial, ya que cada una de las actoras se vincul\u00f3 a la Fundaci\u00f3n Prodesarrollo de la Educaci\u00f3n Pre-escolar del Valle, FUNDAPRE, por medio de un contrato individual de trabajo, mientras que los otros docentes, los vinculados por concurso al departamento, tienen una relaci\u00f3n de trabajo distinta, raz\u00f3n por la cual a dos situaciones de hecho diferentes no se le puede dar una trato igualitario. &nbsp;<\/p>\n<p>De igual modo, consider\u00f3 que en ninguno de los contratos suscritos figuraba el Departamento del valle del Cauca como parte obligada, ni &#8220;esta entidad oficial asum\u00eda all\u00ed obligaciones laborales o prestacionales&#8221; para con las educadoras. Que tampoco se vislumbraba trato discriminatorio en contra de las accionantes, ya que por mandato de la Ley General de Educaci\u00f3n, deb\u00edan cumplir los requisitos a que se refiere el inciso 2\u00b0 del art\u00edculo 105 de la citada Ley 115 de 1994. &nbsp;<\/p>\n<p>En relaci\u00f3n con lo anterior, observa la Sala que de los contratos suscritos entre las accionantes y la Fundaci\u00f3n, no se deduce la posibilidad de vincular jur\u00eddicamente a la Gobernaci\u00f3n del Departamento del Valle del Cauca -Secretar\u00eda de Educaci\u00f3n-, ya que dicho v\u00ednculo solamente obliga a las partes contratantes, en virtud del cual mantienen una relaci\u00f3n de tipo laboral que se rige por los t\u00e9rminos del C\u00f3digo Sustantivo del Trabajo.&nbsp; &nbsp;<\/p>\n<p>De otra parte, cabe anotar que los docentes vinculados a la administraci\u00f3n departamental, lo est\u00e1n de conformidad con el art\u00edculo 125 de la Constituci\u00f3n y del art\u00edculo 105 de la Ley 115 de 1994 Ley General de Educaci\u00f3n, y por tanto ostentan el status de empleados p\u00fablicos, sujetos a un r\u00e9gimen legal y reglamentario, de tal forma que entre \u00e9stos y el departamento existe una relaci\u00f3n jur\u00eddica diferente a la que se configura entre la FUNDAPRE y los educadores vinculados a \u00e9sta mediante contrato de trabajo. &nbsp;<\/p>\n<p>En consecuencia, si las accionantes pretenden ingresar a la planta de personal docente de la administraci\u00f3n, deber\u00e1n reunir los requisitos establecidos en dicha ley, esto es, inscribirse en el concurso una vez la Gobernaci\u00f3n haga la respectiva apertura, haber sido seleccionadas para conformar la planta de docentes como as\u00ed lo indica el precepto mencionado, pues, &#8220;para acceder a un determinado cargo p\u00fablico se deben cumplir todos y cada uno de los requisitos y condiciones se\u00f1alados en la Constituci\u00f3n y la Ley12. La norma citada es del siguiente tenor: &nbsp;<\/p>\n<p>&#8220;La vinculaci\u00f3n de personal docente, directivo y administrativo al servicio p\u00fablico educativo estatal, s\u00f3lo podr\u00e1 efectuarse mediante nombramiento hecho por decreto y dentro de la planta de personal aprobada por la respectiva entidad territorial. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;\u00danicamente podr\u00e1n ser nombrados como educadores o funcionarios administrativos de la educaci\u00f3n estatal, dentro de la planta de personal, quienes previo concurso, hayan sido seleccionados y acrediten los requisitos legales&#8221;. &nbsp;<\/p>\n<p>Los concursos para nombramientos de nuevos docentes ser\u00e1n convocados por los departamentos o distritos; los educadores podr\u00e1n inscribirse en la entidad territorial convocante y como resultado del proceso saldr\u00e1 una lista de elegibles, la cual corresponder\u00e1 al n\u00famero de plazas o cupos para proveer en cada municipio. El Ministerio de Educaci\u00f3n Nacional, por intermedio del Instituto Colombiano para el Fomento de la Educaci\u00f3n Superior, ICFES, establecer\u00e1 un sistema para celebrar los concursos, de tal manera que se asegure la total imparcialidad\u201d. (Subrayado fuera del texto original).&nbsp; &nbsp;<\/p>\n<p>Por lo anterior se deduce que trat\u00e1ndose de dos grupos de docentes vinculados de manera distinta, no obstante cumplir la misma labor, es s\u00f3lo entre los educadores de la Gobernaci\u00f3n (nombrados por acto administrativo), en quienes cabe la aplicaci\u00f3n del derecho fundamental a la igualdad, m\u00e1s no entre \u00e9stos y los que laboran al servicio de FUNDAPRE, raz\u00f3n por la cual no es posible invocar la vulneraci\u00f3n de este derecho fundamental, cuando las partes con las cuales est\u00e1n vinculados los docentes oficiales (la Gobernaci\u00f3n), y los ligados por contrato de trabajo con la entidad privada (FUNDAPRE), son distintas. &nbsp;<\/p>\n<p>Cabe se\u00f1alar que la acci\u00f3n de tutela no es procedente para dirimir situaciones litigiosas con ocasi\u00f3n de la aplicaci\u00f3n de los respectivos contratos, para los efectos del cumplimiento de las obligaciones inherentes a los mismos, ya que en virtud de la jurisprudencia de esta Corporci\u00f3n, dicha definici\u00f3n de la respectiva controversia corresponde a la justicia laboral, con respecto a las diferencias surgidas de la interpretaci\u00f3n del contrato de trabajo. Debe advertirse que en el presente asunto la relaci\u00f3n existente entre el Departamento y la FUNDAPRE no es de car\u00e1cter laboral, sino de naturaleza administrativa que puede derivar obligaciones de la misma \u00edndole con el Departamento. &nbsp;<\/p>\n<p>Al respecto ha expresado la Corte: &nbsp;<\/p>\n<p>\u201c(&#8230;) sobre la posibilidad de promover acci\u00f3n de tutela con miras a resolver controversias o diferencias surgidas entre partes con ocasi\u00f3n de la celebraci\u00f3n o ejecuci\u00f3n de contratos se ha orientado a no admitir, en principio, la procedencia de dicha acci\u00f3n, pues este tipo de conflictos tiene en el ordenamiento jur\u00eddico sus propios mecanismos de soluci\u00f3n y no le es dable al juez de tutela desconocer el principio de la autonom\u00eda e independencia de las dem\u00e1s jurisdicciones (Arts. 228 y 230 C.P.), lo cual tiene su fundamento y explicaci\u00f3n en la circunstancia de que esta clase de controversias aluden b\u00e1sicamente a aspectos desprovistos ordinariamente de relevancia constitucional13. &nbsp;<\/p>\n<p>&#8220;El derecho fundamental objeto de una acci\u00f3n de tutela debe corresponder a una consagraci\u00f3n expresa y positiva efectuada directamente por el Constituyente que decide reservar \u00e1mbitos de la persona de la intromisi\u00f3n estatal o establece prestaciones y garant\u00edas que se incorporan como &nbsp;situaciones activas de poder de los sujetos oponibles al mismo. No tienen ese origen y mal puede pretender confer\u00edrseles ese car\u00e1cter, las situaciones subjetivas activas o pasivas derivadas de la concesi\u00f3n rec\u00edproca de facultades que intercambian entre s\u00ed las partes de un contrato y que constituyen su contenido. &nbsp;<\/p>\n<p>Si bien la contrataci\u00f3n es una manifestaci\u00f3n de la libertad contractual y el ordenamiento le brinda reconocimiento, dentro de ciertos l\u00edmites, hasta el punto de imponer judicialmente su cumplimiento, no por ello los derechos derivados de la matriz del contrato &#8211; que no de la Constituci\u00f3n &#8211; adquieren rango constitucional. &nbsp;<\/p>\n<p>La situaci\u00f3n materia de la tutela, nacida al amparo de un contrato y regulada por \u00e9ste, s\u00f3lo tiene una relevancia constitucional gen\u00e9rica en el sentido de que la fuente pertinente para resolver la controversia es la regla contractual, la cual como toda fuente normativa debe interpretarse de conformidad con la Constituci\u00f3n, sin que por ello la misma o su presupuesto normativo adquieran car\u00e1cter constitucional. Tampoco se est\u00e1 en presencia de una decisi\u00f3n judicial que en el caso planteado haya omitido una consideraci\u00f3n constitucional fundamental que permita concederle al asunto relevancia constitucional directa como para ser avocada por esta Jurisdicci\u00f3n. De hecho, el demandante equivoc\u00f3 la Jurisdicci\u00f3n pues trat\u00e1ndose de un asunto puramente contractual ha debido acudir a la Jurisdicci\u00f3n ordinaria14&#8243;. &nbsp;<\/p>\n<p>Por lo expuesto, se confirmar\u00e1n las providencias materia de revisi\u00f3n. &nbsp;<\/p>\n<p>IV. &nbsp;DECISION &nbsp;<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Sexta de Revisi\u00f3n de Tutela de la Corte Constitucional, obrando en nombre del pueblo y por mandato de la Constituci\u00f3n,&nbsp; &nbsp;<\/p>\n<p>RESUELVE: &nbsp;<\/p>\n<p>Primero. CONFIRMAR la sentencia proferida por el Tribunal Superior del Distrito Judicial de Cali, Sala Civil, el seis (6) de marzo de 1996, que confirm\u00f3 el fallo dictado por el Juzgado Cuarto Civil del Circuito de Santiago de Cali, el veinte (20) de de febrero del mismo a\u00f1o, con respecto a la tutela radicada bajo el n\u00famero T-94.490 cuya accionante es la ciudadana Adriana Posso Vidal, en cuanto neg\u00f3 la tutela de los derechos fundamentales invocados. &nbsp;<\/p>\n<p>Segundo. CONFIRMAR la sentencia proferida por el Tribunal Superior del Distrito Judicial de Cali, el veintisiete (27) de marzo de 1996, que confirm\u00f3 la sentencia proferida por el Juzgado Sexto Civil del Circuito de Cali, el veintiseis (26) de febrero del mismo a\u00f1o, que deneg\u00f3 la tutela formulada por Elsa Elena Andrade S\u00e1nchez, contenida en el expediente n\u00famero T-96.737, por las razones expuestas en la parte motiva de esta providencia. &nbsp;<\/p>\n<p>Tercero. LIBRENSE por secretar\u00eda, las comunicaciones de que trata el art\u00edculo 36 del decreto 2591 de 1991. &nbsp;<\/p>\n<p>Notif\u00edquese, c\u00f3piese, publ\u00edquese, comun\u00edquese a quien corresponda e ins\u00e9rtese en la Gaceta de la Corte Constitucional, env\u00edese al Despacho de origen y c\u00famplase. &nbsp;<\/p>\n<p>HERNANDO HERRERA VERGARA &nbsp;<\/p>\n<p>Magistrado Ponente &nbsp;<\/p>\n<p>ALEJANDRO MARTINEZ CABALLERO &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>FABIO MORON DIAZ &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>MARTHA VICTORIA SACHICA DE MONCALEANO &nbsp;<\/p>\n<p>Secretaria General. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp;<\/p>\n<p>1Corte Constitucional, Sentencia No. 426 de 1992, Magistrado Ponente Dr. Eduardo Cifuentes Mu\u00f1oz. &nbsp;<\/p>\n<p>2Corte Constitucional, Sentencia No. 495 de 1992, Magistrado Ponente Dr. Ciro Angarita Bar\u00f3n. &nbsp;<\/p>\n<p>3Corte Constitucional, Sentencia No. 495 de 1992, Magistrado Ponente Dr. Ciro Angarita Bar\u00f3n. &nbsp;<\/p>\n<p>4Corte Constitucional, Sentencia No. 575 de 1994, Magistrado Ponente Dr. Jos\u00e9 Gregorio Hern\u00e1ndez Galindo. &nbsp;<\/p>\n<p>5Corte Constitucional, Sentencia No. 474 de 1993, Magistrado Ponente Dr. Jos\u00e9 Gregorio Hern\u00e1ndez Galindo. &nbsp;<\/p>\n<p>6Corte Constitucional, Sentencia No. 076 de 1995, Magistrado Ponente Dr. Jorge Arango Mej\u00eda. &nbsp;<\/p>\n<p>7C\u00f3digo Contencioso Administrativo. &nbsp;<\/p>\n<p>8Corte Constitucional, Sentencia No. 076 de 1995, Magistrado Ponente Dr. Jorge Arango Mej\u00eda. &nbsp;<\/p>\n<p>9Corte Constitucional, Sentencia No. 386 de 1993, Magistrado Ponente Dr. Hernando Herrera Vergara. &nbsp;<\/p>\n<p>10Corte Constitucional, Sentencia No. 484 de 1993, Magistrado Ponente Dr. Jos\u00e9 Gregorio Hern\u00e1ndez Galindo. &nbsp;<\/p>\n<p>11Corte Constitucional, Sentencia No. 022 de 1996, Magistrado Ponente Dr. Carlos Gaviria D\u00edaz. &nbsp;<\/p>\n<p>12Corte Constitucional, Sentencia No. 555 de 1994, Magistrado Ponente Dr. Eduardo Cifuentes Mu\u00f1oz. &nbsp;<\/p>\n<p>13Corte Constitucional, Sentencia No. 605 de 1995, Magistrado Ponente Dr. Antonio Barrera Carbonell. &nbsp;<\/p>\n<p>14Corte Constitucional, Sentencia No. 240 de 1993, Magistrado Ponente Dr. Eduardo Cifuentes Mu\u00f1oz. &nbsp;<\/p>\n<p>8 &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>T-406-96 &nbsp; &nbsp; Expediente T-96.084 &nbsp; Sentencia T-406\/96 &nbsp; CONTRATO DE TRABAJO DE PERSONAL DOCENTE-Solicitud vinculaci\u00f3n departamental &nbsp; Trat\u00e1ndose de dos grupos de docentes vinculados de manera distinta, no obstante cumplir la misma labor, es s\u00f3lo entre los educadores de la Gobernaci\u00f3n, en quienes cabe la aplicaci\u00f3n del derecho fundamental a la igualdad, m\u00e1s no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-2582","post","type-post","status-publish","format-standard","hentry","category-tutelas-1996"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/2582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=2582"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/2582\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=2582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=2582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=2582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}