{"id":25893,"date":"2024-06-28T20:12:45","date_gmt":"2024-06-28T20:12:45","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/06\/28\/su024-18\/"},"modified":"2024-06-28T20:12:45","modified_gmt":"2024-06-28T20:12:45","slug":"su024-18","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/su024-18\/","title":{"rendered":"SU024-18"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0SU024-18 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia SU024\/18 \u00a0 \u00a0<\/p>\n<p>DERECHO DE ACCESO EFECTIVO A LA \u00a0 ADMINISTRACION DE JUSTICIA EN MATERIA DE TUTELA-Posibilidad de acudir ante cualquier \u00a0 Juez o Cuerpo colegiado para interponer la acci\u00f3n de tutela o directamente ante \u00a0 la Corte Constitucional \u00a0 \u00a0<\/p>\n<p>Toda autoridad judicial en su condici\u00f3n de juez constitucional \u00a0 y sin excepci\u00f3n alguna, est\u00e1 obligada a conocer las acciones de tutela \u00a0 promovidas por las personas que consideren que sus derechos fundamentales se \u00a0 est\u00e1n viendo amenazados o transgredidos. \u00a0 \u00a0<\/p>\n<p>ACCION DE \u00a0 TUTELA CONTRA PROVIDENCIAS JUDICIALES-Reiteraci\u00f3n de jurisprudencia sobre \u00a0 procedencia excepcional\u00a0 \u00a0 \u00a0<\/p>\n<p>ACCION DE \u00a0 TUTELA CONTRA PROVIDENCIAS JUDICIALES-Requisitos generales y especiales de \u00a0 procedibilidad \u00a0 \u00a0<\/p>\n<p>VIOLACION DIRECTA DE LA CONSTITUCION \u00a0 COMO CAUSAL DE PROCEDIBILIDAD DE LA ACCION DE TUTELA CONTRA PROVIDENCIAS \u00a0 JUDICIALES \u00a0 \u00a0<\/p>\n<p>PENSION DE INVALIDEZ-Requisitos para obtener reconocimiento \u00a0 y pago \u00a0 \u00a0<\/p>\n<p>Actualmente se exigen dos requisitos para acceder a la pensi\u00f3n de invalidez (i) \u00a0 tener una p\u00e9rdida de capacidad laboral igual o superior al 50%, y (ii) haber \u00a0 cotizado como m\u00ednimo cincuenta (50) semanas en los tres (3) a\u00f1os inmediatamente \u00a0 anteriores a la fecha de estructuraci\u00f3n de la invalidez.\u00a0 \u00a0 \u00a0<\/p>\n<p>ACCION DE \u00a0 TUTELA CONTRA PROVIDENCIAS JUDICIALES-Procedencia por incurrir en violaci\u00f3n \u00a0 directa de la Constituci\u00f3n al aplicar norma declarada inconstitucional para \u00a0 acceder a pensi\u00f3n de invalidez \u00a0 \u00a0<\/p>\n<p>En esta medida, exigir el cumplimiento del requisito de fidelidad para acceder a \u00a0 reconocer y pagar una pensi\u00f3n de invalidez es inconstitucional, pues el mismo \u00a0 fue excluido del ordenamiento por la Corte Constitucional mediante Sentencia \u00a0 C-428 de 2009, al considerarse regresivo y gravoso para el solicitante, decisi\u00f3n \u00a0 que hizo tr\u00e1nsito a cosa juzgada y tiene efectos erga omnes, por tanto es de \u00a0 obligatorio cumplimiento.\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>Referencia: Expediente T- 6.221.520 \u00a0 \u00a0<\/p>\n<p>Acci\u00f3n de tutela instaurada por Elizabeth Lenis Mora \u00a0 contra la Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia. \u00a0 \u00a0<\/p>\n<p>Magistrada Ponente: \u00a0 \u00a0<\/p>\n<p>CRISTINA PARDO SCHLESINGER \u00a0 \u00a0<\/p>\n<p>Bogot\u00e1 D.C., cinco (5) de abril de dos mil \u00a0 dieciocho (2018). \u00a0 \u00a0<\/p>\n<p>La Sala Plena de la Corte Constitucional, \u00a0conformada por los magistrados Alejandro \u00a0 Linares Cantillo -quien la preside-, Carlos Bernal Pulido, Diana Fajardo, Luis Guillermo Guerrero P\u00e9rez, Antonio Jos\u00e9 \u00a0 Lizarazo, Gloria Stella Ortiz Delgado, Cristina Pardo \u00a0 Schlesinger, Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos, en ejercicio de sus competencias constitucionales y legales, \u00a0 y espec\u00edficamente las previstas en los art\u00edculos 86 y 241 numeral 9\u00b0 de la \u00a0 Constituci\u00f3n Pol\u00edtica, profiere la siguiente\u00a0 \u00a0 \u00a0<\/p>\n<p>SENTENCIA \u00a0 \u00a0<\/p>\n<p>En el proceso de revisi\u00f3n de la decisi\u00f3n adoptada por la Sala de \u00a0 Casaci\u00f3n Civil de la Corte Suprema de Justicia el 13 de julio de 2012, donde se \u00a0 abstuvo de dar tr\u00e1mite a la acci\u00f3n de tutela interpuesta por la se\u00f1ora Elizabeth \u00a0 Lenis Mora contra la Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia. \u00a0 \u00a0<\/p>\n<p>I.\u00a0\u00a0\u00a0 \u00a0ANTECEDENTES \u00a0 \u00a0<\/p>\n<p>La se\u00f1ora Elizabeth Lenis Mora, a trav\u00e9s de \u00a0 apoderado judicial, present\u00f3 acci\u00f3n de tutela en contra de la Sala de Casaci\u00f3n \u00a0 Laboral de la Corte Suprema de Justicia, al considerar vulnerado su derecho \u00a0 fundamental al debido proceso dentro del proceso laboral adelantado contra la \u00a0 Sociedad Administradora de Fondos de Pensiones y cesant\u00edas PORVENIR S.A, \u00a0 tendiente a obtener el pago de la pensi\u00f3n de invalidez que culmin\u00f3 con la \u00a0 sentencia dictada el 22 de noviembre de 2011, donde se niegan las pretensiones \u00a0 de la demandante y no se le da aplicaci\u00f3n a la Sentencia C-428 de 2009, la cual \u00a0 declar\u00f3 inconstitucional el requisito de fidelidad al sistema para poder obtener \u00a0 la pensi\u00f3n de invalidez. Basa su solicitud en los siguientes hechos \u00a0 \u00a0<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Hechos y argumentos de derecho \u00a0 \u00a0<\/p>\n<p>1.1.\u00a0\u00a0\u00a0 El 20 de diciembre de 2006 la se\u00f1ora \u00a0 Elizabeth Lenis Mora[1] \u00a0fue calificada por el Grupo Interdisciplinario de Seguros Alfa S.A con un \u00a0 porcentaje de p\u00e9rdida de capacidad laboral del 67.37%, con fecha de \u00a0 estructuraci\u00f3n el 2 de agosto de 2006.\u00a0 A partir de dicho dictamen, \u00a0 solicit\u00f3 el reconocimiento y pago de su pensi\u00f3n de invalidez. Sin embargo, \u00a0 PORVENIR S.A. neg\u00f3 dicho reconocimiento, mediante oficio del 5 de marzo de 2007, \u00a0 tras considerar que no cumpl\u00eda con el requisito de fidelidad al sistema. \u00a0 \u00a0<\/p>\n<p>1.2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Manifiesta la \u00a0 accionante que ante tal negativa, interpuso la correspondiente demanda laboral, \u00a0 la cual correspondi\u00f3 en primera instancia al Juzgado 5 Laboral del Circuito de \u00a0 Cali, quien mediante fallo del 30 de abril de 2009 neg\u00f3 las pretensiones de la \u00a0 demandante. Impugnada dicha decisi\u00f3n, conoci\u00f3 la Sala Laboral del Tribunal \u00a0 Superior de Cali, la cual en sentencia del 28 de octubre de 2009 resolvi\u00f3 \u00a0 revocar la decisi\u00f3n de primera instancia e inaplicar por excepci\u00f3n de \u00a0 inconstitucionalidad el requisito de fidelidad al sistema. En virtud de esta \u00a0 decisi\u00f3n se orden\u00f3 a la sociedad administradora de pensiones y cesant\u00edas \u00a0 PORVENIR S.A reconocer y pagar la pensi\u00f3n de invalidez a la se\u00f1ora Elizabeth \u00a0 Lenis Mora. Sin embargo, PORVENIR S.A. present\u00f3 recurso extraordinario de \u00a0 casaci\u00f3n, el cual fue admitido por la Sala de Casaci\u00f3n Laboral de la Corte \u00a0 Suprema de Justicia, la cual mediante fallo del 22 de noviembre de 2011 confirm\u00f3 \u00a0 la decisi\u00f3n proferida por el juzgado de primera instancia. Explic\u00f3 la Corte \u00a0 Suprema de Justicia que la sentencia C-428 de 2009 no era aplicable al caso de \u00a0 la accionante, por cuanto la Corte Constitucional no le hab\u00eda otorgado a la \u00a0 citada sentencia efectos retroactivos. \u00a0 \u00a0<\/p>\n<p>1.3.\u00a0\u00a0\u00a0 Luego de agotar el tr\u00e1mite ante la \u00a0 jurisdicci\u00f3n laboral y actuando a trav\u00e9s de apoderado judicial, la se\u00f1ora Lenis \u00a0 Mora present\u00f3 acci\u00f3n de tutela contra la Sala de Casaci\u00f3n Laboral de la Corte \u00a0 Suprema de Justicia, por considerar que no aplicar la sentencia C-428 de 2009 en \u00a0 su caso, supuso la vulneraci\u00f3n de su derecho fundamental al debido proceso, y el \u00a0 desconocimiento de los art\u00edculos 4[2] \u00a0y 243[3] \u00a0de la Constituci\u00f3n, por cuanto se emple\u00f3 una norma de car\u00e1cter regresivo y se \u00a0 incurri\u00f3 en la prohibici\u00f3n constitucional de reproducir una norma que ya hab\u00eda \u00a0 sido retirada del ordenamiento jur\u00eddico. Por tal motivo solicit\u00f3 que se dictara \u00a0 una nueva sentencia. \u00a0 \u00a0<\/p>\n<p>1.4.\u00a0\u00a0\u00a0 Conforme a lo expuesto solicita se tutele su \u00a0 derecho fundamental al debido proceso que a su juicio result\u00f3 conculcado con la \u00a0 sentencia proferida el 22 de noviembre de 2011 por la Sala Laboral de la Corte \u00a0 Suprema de Justicia, dentro del proceso laboral adelantado contra la Sociedad \u00a0 Administradora de Fondos de Pensiones y cesant\u00edas PORVENIR S.A. y en \u00a0 consecuencia, se dicte sentencia cuyos fundamentos se ajustar\u00e1n a los preceptos \u00a0 constitucionales contenidos en la sentencia de constitucionalidad ya mencionada. \u00a0 \u00a0<\/p>\n<p>2.\u00a0 \u00a0Tr\u00e1mite Procesal \u00a0 \u00a0<\/p>\n<p>2.1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0La presente acci\u00f3n \u00a0 de tutela fue conocida en primera instancia por la Sala de Casaci\u00f3n Penal de la \u00a0 Corte Suprema de Justicia, la cual, en providencia del 19 de junio de 2012 \u00a0 declar\u00f3 improcedente el amparo incoado. \u00a0 \u00a0<\/p>\n<p>2.2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0Inconforme con esta \u00a0 decisi\u00f3n, la accionante present\u00f3 la correspondiente impugnaci\u00f3n, que fue \u00a0 conocida por la Sala de Casaci\u00f3n Civil de ese mismo Tribunal, la cual en \u00a0 decisi\u00f3n del 13 de julio de la misma anualidad declar\u00f3 la nulidad de todo lo \u00a0 actuado desde el momento en que se orden\u00f3 el tr\u00e1mite de la acci\u00f3n de tutela, y \u00a0 en su lugar orden\u00f3 no admitir la misma, por cuanto su admisi\u00f3n implicar\u00eda \u00a0 desconocer la intangibilidad de las decisiones proferidas en sede de casaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>2.3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Teniendo en cuenta \u00a0 que la autoridad judicial citada se abstuvo de estudiar de fondo su caso, en \u00a0 virtud de lo dispuesto en el Auto 100 de 2008[4] \u00a0el 31 de mayo de 2017 la accionante procedi\u00f3 a presentar de forma directa ante \u00a0 la Secretar\u00eda General de esta Corporaci\u00f3n, la acci\u00f3n de tutela para que se \u00a0 surtiera el tr\u00e1mite de selecci\u00f3n respectivo. \u00a0 \u00a0<\/p>\n<p>2.4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0As\u00ed, la Sala de \u00a0 Selecci\u00f3n n\u00famero Siete, mediante auto del 11 de julio de 2017, seleccion\u00f3 la \u00a0 presente acci\u00f3n de tutela y la reparti\u00f3 a la Sala S\u00e9ptima de Revisi\u00f3n de \u00a0 Tutelas. \u00a0 \u00a0<\/p>\n<p>2.5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0Mediante auto del \u00a0 18 de agosto de 2017, la magistrada sustanciadora orden\u00f3 la pr\u00e1ctica de algunas \u00a0 pruebas que le permitieran obtener \u00a0 elementos de juicio necesarios para adoptar una decisi\u00f3n, espec\u00edficamente con el \u00a0 objeto de determinar si resultaba procedente la solicitud de amparo en el \u00a0 presente asunto. Para ello solicit\u00f3: \u201c(i) a la Sala de Casaci\u00f3n Laboral de la \u00a0 Corte Suprema de Justicia, que remita copia del proceso laboral adelantado por \u00a0 la se\u00f1ora Elizabeth Lenis Mora contra la Sociedad Administradora de Fondos de \u00a0 Pensiones y cesant\u00edas PORVENIR S.A, tendiente a obtener el pago de la pensi\u00f3n de \u00a0 invalidez; (ii) a la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia que \u00a0 remita copia del expediente de tutela instaurado por Elizabeth Lenis Mora contra \u00a0 la Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia y (iii) a la se\u00f1ora \u00a0 Elizabeth Lenis Mora (actora dentro del proceso de la referencia) que informe a \u00a0 este despacho las actuaciones que ha realizado desde el a\u00f1o 2012, tendientes a \u00a0 obtener el reconocimiento y pago de su pensi\u00f3n de invalidez\u201d. \u00a0 \u00a0<\/p>\n<p>En el mismo auto, y en aras de garantizar el derecho de \u00a0 defensa de la autoridad accionada, \u00a0 resolvi\u00f3 poner en conocimiento de la Sala de Casaci\u00f3n Laboral de la Corte \u00a0 Suprema de Justicia y del Juzgado Quinto Laboral del Circuito de Cali el \u00a0 contenido de la acci\u00f3n de tutela con el objetivo de que se pronunciaran sobre la \u00a0 misma, para lo cual se envi\u00f3 copia del escrito de tutela. \u00a0 \u00a0<\/p>\n<p>2.6.\u00a0\u00a0\u00a0 \u00a0Posteriormente, el 4 \u00a0 de septiembre de 2017, solicit\u00f3 al Juzgado \u00a0 Quinto Laboral del Circuito de Cali, \u201cremitir copia del expediente del \u00a0 proceso laboral adelantado por la se\u00f1ora Elizabeth Lenis Mora contra la Sociedad \u00a0 Administradora de Fondos de Pensiones y cesant\u00edas PORVENIR S.A, tendiente a \u00a0 obtener el pago de la pensi\u00f3n de invalidez, el cual ya se encuentra en su \u00a0 despacho\u201d. Lo anterior conforme a lo establecido por la Sala de Casaci\u00f3n \u00a0 Laboral de la Corte Suprema de Justicia mediante oficio remitido a esta Corte el \u00a0 25 de agosto de esta anualidad[5]. \u00a0 \u00a0<\/p>\n<p>2.7.\u00a0\u00a0\u00a0 \u00a0Mediante auto del diecinueve \u00a0 (19) de septiembre de dos mil diecisiete (2017), la Magistrada Sustanciadora \u00a0 solicit\u00f3 a la Sociedad \u00a0 Administradora de Fondos de Pensiones y Cesant\u00edas PORVENIR S.A: (i) copia de la \u00a0 historia laboral de la se\u00f1ora Elizabeth Lenis Mora y (ii) explicaci\u00f3n acerca de \u00a0 los motivos exactos por los cuales le fue negada la pensi\u00f3n de invalidez de la \u00a0 accionante.\u00a0 \u00a0 \u00a0<\/p>\n<p>2.8.\u00a0\u00a0\u00a0 Pruebas obrantes en el expediente \u00a0 \u00a0<\/p>\n<p>2.8.1. Copia informal de la sentencia proferida el 22 de \u00a0 noviembre de 2011 por la Sala de Casaci\u00f3n Laboral de la Corte Suprema de \u00a0 Justicia, relacionado con el recurso extraordinario de casaci\u00f3n interpuesto por \u00a0 la Sociedad Administradora de Fondos y Pensiones PORVENIR S.A en el juicio que \u00a0 promovi\u00f3 Elisabeth Lenis Mora (Folios 45-118, cuaderno No.2). \u00a0 \u00a0<\/p>\n<p>2.8.2. Copia informal del auto del 19 de junio de 2012, \u00a0 mediante el cual la Sala de Casaci\u00f3n Penal de la Corte Suprema de Justicia \u00a0 declara la improcedencia de la acci\u00f3n (Folios 9-10, cuaderno No. 2). \u00a0 \u00a0<\/p>\n<p>2.8.3. Copia informal del auto del 13 de julio de 2012, \u00a0 mediante el cual la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia \u00a0 resuelve declarar la nulidad de todo lo actuado en la acci\u00f3n de tutela desde el \u00a0 momento en que se orden\u00f3 darle tr\u00e1mite. (Folios 11-18, cuaderno No. 2). \u00a0 \u00a0<\/p>\n<p>2.8.4. Copia informal de la historia cl\u00ednica de la se\u00f1ora \u00a0 Elisabeth Lenis Mora (folios 19-26, cuaderno No.2). \u00a0 \u00a0<\/p>\n<p>2.9.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0Pruebas \u00a0 aportadas ante la Corte Constitucional \u00a0 \u00a0<\/p>\n<p>2.8.1\u00a0\u00a0\u00a0 Mediante oficio del 31 de agosto de 2017, la \u00a0 se\u00f1ora Elisabeth Lenis Mora,\u00a0 en respuesta al oficio enviado por la \u00a0 Magistrada Sustanciadora, referente a las actuaciones realizadas desde el a\u00f1o \u00a0 2012, tendientes a obtener el reconocimiento y pago de su pensi\u00f3n de vejez \u00a0 se\u00f1al\u00f3:\u00a0 \u201c(\u2026) la acci\u00f3n de tutela que deb\u00ed promover para intentar que \u00a0 los jueces entraran en raz\u00f3n de que yo si ten\u00eda derecho a la pensi\u00f3n, pues como \u00a0 me fue explicado con la condici\u00f3n de invalidez que padezco y las semanas que \u00a0 tengo cotizadas me daba para recibir mi pensi\u00f3n (\u2026) fue a finales del a\u00f1o 2012 \u00a0 que me enter\u00e9 definitivamente que la tutela no era procedente y que ya no ten\u00eda \u00a0 como reclamar este derecho (\u2026) nuevamente consulte con otro abogado y \u00e9l me \u00a0 explic\u00f3 que si ten\u00eda derecho a la pensi\u00f3n y le reclamamos a Porvenir el 30 de \u00a0 mayo de 2017 (\u2026) Porvenir en una carta del 30 de junio de 2017 me dijo que no \u00a0 ten\u00eda derecho a la pensi\u00f3n porque ya hab\u00eda demandado y hab\u00eda perdido la demanda \u00a0 (\u2026) aun continuo enferma y no tengo un empleo estable\u201d[6]. \u00a0 \u00a0<\/p>\n<p>2.8.2\u00a0\u00a0\u00a0 Mediante oficio del 25 de agosto de 2017, la \u00a0 Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia inform\u00f3 a este \u00a0 Despacho: \u201cRespecto del oficio No. OPTB-2385\/17 del 23 de agosto de este a\u00f1o, \u00a0 librado dentro de la acci\u00f3n de tutela de la referencia, relacionado con el \u00a0 recurso extraordinario de casaci\u00f3n interpuesto por la Sociedad Administradora de \u00a0 Fondos y Pensiones PORVENIR S.A (\u2026) anexo copia de la sentencia proferida el 22 \u00a0 de noviembre de 2011 mediante la cual se desat\u00f3 el recurso extraordinario de \u00a0 casaci\u00f3n. En cuanto al env\u00edo de la copia del proceso, le comunico que no es \u00a0 posible acceder a ella por cuanto el mismo se remiti\u00f3 al Tribunal de origen, \u00a0 desde el 21 de marzo de 2012, con oficio No. 3023\u201d. \u00a0 \u00a0<\/p>\n<p>2.8.3\u00a0\u00a0\u00a0 Mediante oficio del 8 de septiembre de 2017, \u00a0 recibido en este despacho el 19 del mismo mes y anualidad, el Juzgado Quinto \u00a0 Laboral del Circuito de Cali remiti\u00f3 copia en CD del proceso ordinario \u00a0 adelantado por la se\u00f1ora Elizabeth Lenis Mora contra la Sociedad Administradora \u00a0 de Pensiones y Cesant\u00edas Porvenir S.A[7]. \u00a0 \u00a0<\/p>\n<p>2.8.4\u00a0\u00a0\u00a0 La Sociedad Administradora de Pensiones y \u00a0 Cesant\u00edas Porvenir S.A,[8] \u00a0mediante escrito del 25 de septiembre de 2017 y luego de hacer un resumen de los \u00a0 hechos y actuaciones judiciales, manifest\u00f3 que no ha vulnerado los derechos de \u00a0 la accionante en la medida que el rechazo de la prestaci\u00f3n solicitada obedeci\u00f3 \u00a0 al estricto cumplimiento de lo ordenado en la decisi\u00f3n de la Corte Suprema de \u00a0 Justicia. Igualmente, indic\u00f3 que no se evidencia vulneraci\u00f3n \u201ccomo quiera que \u00a0 a la fecha no ha sido radicada la reclamaci\u00f3n pensional.\u201d \u00a0 \u00a0<\/p>\n<p>Agreg\u00f3 que en este caso, las pretensiones \u00a0 fueron resueltas en una oportunidad anterior por lo que se ha configurado la \u00a0 cosa juzgada respecto de las decisiones proferidas por los jueces de la \u00a0 jurisdicci\u00f3n ordinaria. Raz\u00f3n por la cual considera improcedente la presente \u00a0 acci\u00f3n de tutela. \u00a0 \u00a0<\/p>\n<p>II.\u00a0\u00a0\u00a0\u00a0 \u00a0CONSIDERACIONES \u00a0 DE LA CORTE CONSTITUCIONAL \u00a0 \u00a0<\/p>\n<p>1.\u00a0 \u00a0Competencia \u00a0 \u00a0<\/p>\n<p>Si bien a la Sala S\u00e9ptima\u00a0de Revisi\u00f3n de Tutelas le fue repartido el presente expediente de \u00a0 tutela para su revisi\u00f3n, los t\u00e9rminos del proceso se suspendieron inicialmente \u00a0 el d\u00eda 7 de septiembre de 2017,[9] y levantados el d\u00eda siguiente, es \u00a0 decir el 8 de septiembre de la misma anualidad. Posteriormente y en cumplimiento \u00a0 a lo dispuesto en el art\u00edculo 31 del Acuerdo 02 de 2015 que unifica y actualiza \u00a0 el Acuerdo 05 de 1992 relativo al reglamento de la Corte Constitucional, y \u00a0 atendiendo al hecho de que la acci\u00f3n de tutela de la referencia se present\u00f3 \u00a0 contra una providencia judicial emitida por la Sala de Casaci\u00f3n Laboral de la \u00a0 Corte Suprema de Justicia, la Magistrada Sustanciadora solicit\u00f3 que el caso \u00a0 fuese asumido por la Sala Plena para su conocimiento. As\u00ed, en sesi\u00f3n del 20 de \u00a0 septiembre de 2017, la Sala Plena decidi\u00f3 asumir el estudio del expediente de la \u00a0 referencia. \u00a0 \u00a0<\/p>\n<p>Por tal motivo y de conformidad con lo \u00a0 dispuesto en el art\u00edculo 59 del Acuerdo 02 de 2015, los t\u00e9rminos del presente \u00a0 proceso fueron suspendidos a partir del 20 de septiembre de 2017.[10] \u00a0 \u00a0<\/p>\n<p>2.\u00a0 \u00a0Problema Jur\u00eddico \u00a0 \u00a0<\/p>\n<p>2.1. Visto el tr\u00e1mite judicial rese\u00f1ado y entendiendo \u00a0 el contexto f\u00e1ctico que motiv\u00f3 la interposici\u00f3n de esta acci\u00f3n de tutela, en la \u00a0 que se alega la vulneraci\u00f3n del derecho al debido proceso en el tr\u00e1mite de una \u00a0 demanda ordinaria laboral,[11] \u00a0la demandante pide que se revoque la providencia proferida por la Sala de \u00a0 Casaci\u00f3n Laboral de la Corte Suprema de Justicia del 22 de noviembre de 2011, en \u00a0 el curso del proceso laboral referido, y en su lugar, se tenga en consideraci\u00f3n \u00a0 que el requisito de fidelidad exigido fue declarado inexequible por la Corte \u00a0 Constitucional mediante Sentencia C-428 de 2009. \u00a0 \u00a0<\/p>\n<p>Conforme a lo anterior y \u00a0 teniendo en cuenta las consideraciones que llevaron a la Sala Plena a asumir el \u00a0 conocimiento del presente caso, le corresponde determinar si la Sala de Casaci\u00f3n Laboral de \u00a0 la Corte Suprema de Justicia \u00a0vulner\u00f3 los derechos fundamentales al debido proceso y al acceso a la \u00a0 administraci\u00f3n de justicia de la accionante, al exigirle el requisito de \u00a0 fidelidad al sistema para poder acceder a su pensi\u00f3n de invalidez, el cual fue \u00a0 declarado inexequible por la Corte Constitucional en sentencia C-428 de 2009. \u00a0 \u00a0<\/p>\n<p>Para solucionar el problema jur\u00eddico \u00a0 planteado, estima la Sala necesario reiterar algunas materias que han sido \u00a0 desarrolladas por esta Corporaci\u00f3n, como: Primero, el acceso efectivo a la administraci\u00f3n de \u00a0 justicia en materia de tutela. Posibilidad de acudir ante cualquier juez o \u00a0 cuerpo colegiado para interponer la acci\u00f3n de tutela o directamente ante la \u00a0 Corte Constitucional. Segundo, la \u00a0 procedencia excepcional de la acci\u00f3n de tutela contra providencias judiciales, \u00a0 los requisitos generales y las \u00a0 causales especiales de procedibilidad \u00a0 excepcional de la acci\u00f3n de tutela contra providencias judiciales. Tercero, \u00a0 requisitos para acceder a la pensi\u00f3n de invalidez. Con base en el estudio \u00a0 anterior, se resolver\u00e1 el caso concreto. \u00a0 \u00a0<\/p>\n<p>3.\u00a0 \u00a0Acceso efectivo a la \u00a0 administraci\u00f3n de justicia en materia de tutela. Posibilidad de acudir ante \u00a0 cualquier juez o cuerpo colegiado para interponer la acci\u00f3n de tutela o \u00a0 directamente ante la Corte Constitucional \u00a0 \u00a0<\/p>\n<p>3.1. La Constituci\u00f3n Pol\u00edtica en su art\u00edculo 86 se\u00f1ala que toda persona \u00a0 tiene la posibilidad de instaurar acci\u00f3n de tutela para reclamar ante los \u00a0 jueces, en todo momento y lugar, la protecci\u00f3n inmediata de sus derechos \u00a0 constitucionales fundamentales, cuando quiera que \u00e9stos resulten amenazados o \u00a0 vulnerados por la acci\u00f3n o la omisi\u00f3n de cualquier autoridad p\u00fablica. De igual \u00a0 forma, precisa que en todo caso, las decisiones adoptadas en esta materia se \u00a0 remitir\u00e1n a la Corte Constitucional para su eventual revisi\u00f3n. Lo anterior, \u00a0 conforme a lo estipulado en el numeral 9 del art\u00edculo 241 Superior, que asigna \u00a0 como funci\u00f3n a la Corte Constitucional la de revisar las decisiones judiciales \u00a0 relacionadas con la acci\u00f3n de tutela de los derechos constitucionales, en la \u00a0 forma que determine la ley. \u00a0 \u00a0<\/p>\n<p>3.2. En el mismo sentido el Decreto 2591 de 1991 en su art\u00edculo 1\u00ba \u00a0 dispone que \u201cToda persona tendr\u00e1 acci\u00f3n de tutela para reclamar ante los \u00a0 jueces, en todo momento y lugar, mediante un procedimiento preferente y sumario, \u00a0 por s\u00ed misma o por quien act\u00fae a su nombre, la protecci\u00f3n inmediata de sus \u00a0 derechos constitucionales fundamentales, cuando quiera que \u00e9stos resulten \u00a0 vulnerados por la acci\u00f3n o la omisi\u00f3n de cualquier autoridad p\u00fablica o de los \u00a0 particulares en los casos que se\u00f1ale este Decreto. Todos los d\u00edas y horas son \u00a0 h\u00e1biles para interponer la acci\u00f3n de tutela\u201d. \u00a0 \u00a0<\/p>\n<p>Este Decreto, tambi\u00e9n plantea algunas situaciones excepcionales seg\u00fan \u00a0 las cuales el juez constitucional no estar\u00eda obligado a adoptar una decisi\u00f3n de \u00a0 fondo en el tr\u00e1mite de una acci\u00f3n de tutela. Estos supuestos son los siguientes:[12] \u00a0 \u00a0<\/p>\n<p>i.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Cuando no sea posible determinar \u00a0 el hecho o la raz\u00f3n que motiva la solicitud de la tutela, en ese caso el juez \u00a0 debe prevenir al solicitante para que en el t\u00e9rmino de tres d\u00edas para que la \u00a0 corrija, de lo contrario la petici\u00f3n puede ser rechazada.[13] \u00a0 \u00a0<\/p>\n<p>ii.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Cesaci\u00f3n de la actuaci\u00f3n \u00a0 impugnada. \u201cSi estando en curso la tutela, se dictare resoluci\u00f3n, administrativa \u00a0 o judicial, que revoque, detenga o suspenda la actuaci\u00f3n impugnada, se declarar\u00e1 \u00a0 fundada la solicitud \u00fanicamente para efectos de indemnizaci\u00f3n y de costas, si \u00a0 fueren procedentes\u201d.[14] \u00a0 \u00a0<\/p>\n<p>iii.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Desistimiento del recurrente. \u00a0 \u201cEl recurrente podr\u00e1 desistir de la tutela, en cuyo caso se archivar\u00e1 el \u00a0 expediente\u201d.[15] \u00a0Cabe aclarar que si el desistimiento se presenta a partir de una satisfacci\u00f3n \u00a0 extraprocesal de los derechos reclamados por el interesado, es posible reabrir \u00a0 la actuaci\u00f3n si se logra demostrar el incumplimiento del acuerdo a partir del \u00a0 cual se arrib\u00f3 al desistimiento.[16] \u00a0 \u00a0<\/p>\n<p>iv.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Finalmente en caso de temeridad, \u00a0 esto es que se presenten los elementos que la jurisprudencia ha denominado como \u00a0 triple identidad,[17] \u00a0los jueces cuentan con la facultad para rechazar de plano o decidir \u00a0 desfavorablemente la solicitud de amparo.[18] \u00a0 \u00a0<\/p>\n<p>3.3. De lo anterior, se puede concluir que toda autoridad judicial en su \u00a0 condici\u00f3n de juez constitucional y sin excepci\u00f3n alguna, est\u00e1 obligada a conocer \u00a0 las acciones de tutela promovidas por las personas que consideren que sus \u00a0 derechos fundamentales se est\u00e1n viendo amenazados o transgredidos. \u00a0 \u00a0<\/p>\n<p>\u201ces evidente que lo resuelto por las diferentes Salas \u00a0 de Casaci\u00f3n de la Corte Suprema de Justicia al no admitir a tr\u00e1mite las acciones \u00a0 de tutela que interponen las personas contra providencia judicial proferida por \u00a0 una Sala de dicha Corporaci\u00f3n, les vulnera su derecho constitucional fundamental \u00a0 de acceso a la administraci\u00f3n de justicia (C.N., art. 229) y a obtener la tutela \u00a0 judicial efectiva de sus derechos fundamentales, de conformidad con los Tratados \u00a0 Internacionales (Convenci\u00f3n Americana de Derechos Humanos, art. 25), y las \u00a0 Opiniones Consultivas de la Corte Interamericana de Derechos Humanos (OC-11\/90, \u00a0 OC-16\/99). \u00a0 \u00a0<\/p>\n<p>(\u2026) \u00a0 \u00a0<\/p>\n<p>[P]ara los casos en que exista la misma situaci\u00f3n de \u00a0 vulneraci\u00f3n del derecho fundamental de acceso a la administraci\u00f3n de justicia y \u00a0 la no tutela judicial efectiva de sus derechos fundamentales, los ciudadanos \u00a0 tienen el derecho de acudir ante cualquier juez (unipersonal o colegiado), \u00a0 incluyendo una Corporaci\u00f3n de igual jerarqu\u00eda a la Corte Suprema de Justicia, \u00a0 para reclamar mediante una acci\u00f3n de tutela la protecci\u00f3n del derecho \u00a0 fundamental que consideran violado con la actuaci\u00f3n de una Sala de Casaci\u00f3n de \u00a0 la Corte Suprema de Justicia.\u201d[20] \u00a0 \u00a0<\/p>\n<p>Como se observa, esta opci\u00f3n propuesta por v\u00eda jurisprudencial aseguraba no solo \u00a0 (i) el acceso efectivo a la administraci\u00f3n de justicia y (ii) la tutela efectiva \u00a0 de los derechos fundamentales presuntamente conculcados, sino que adem\u00e1s (iii) \u00a0 garantizaba la protecci\u00f3n del derecho al debido proceso, al permitir que la \u00a0 acci\u00f3n de tutela tuviera las instancias judiciales propias de su tr\u00e1mite \u00a0 constitucional se\u00f1alado en el art\u00edculo 86 de la Carta. \u00a0 \u00a0<\/p>\n<p>3.5. Posteriormente, en el a\u00f1o 2008, la Corte \u00a0 Constitucional observ\u00f3 la persistente negativa de algunas Salas de Casaci\u00f3n de \u00a0 la Corte Suprema de Justicia de admitir las acciones de tutela presentadas \u00a0 contra sus decisiones, raz\u00f3n por la que la Sala Plena profiri\u00f3 el Auto 100, \u00a0 mediante el cual otorg\u00f3 a los accionantes la posibilidad, no solo de presentar \u00a0 la acci\u00f3n de tutela ante cualquier otro juez de la Rep\u00fablica, sino que permiti\u00f3 \u00a0 hacerlo directamente ante la Secretar\u00eda General de la misma Corporaci\u00f3n, con la \u00a0 finalidad de adelantar el tr\u00e1mite de selecci\u00f3n. Al respecto indic\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cDebido a la efectiva conculcaci\u00f3n de los derechos \u00a0 fundamentales de acceso a la administraci\u00f3n de justicia y de tutela judicial \u00a0 efectiva de los accionantes que puede tener lugar en casos similares al \u00a0 estudiado en la presente decisi\u00f3n, en el cual a pesar que el peticionario hizo \u00a0 uso de la regla fijada en el Auto 04 de 2004 y ante la negativa de la Corte \u00a0 Suprema de Justicia a admitir la acci\u00f3n instaurada acudi\u00f3 ante otras autoridades \u00a0 judiciales las cuales tampoco abocaron el conocimiento de la petici\u00f3n \u00a0 presentada, en adelante, cuando se presente una situaci\u00f3n semejante en la cual \u00a0 la Corte Suprema de Justicia no admita a tr\u00e1mite una acci\u00f3n de tutela contra una \u00a0 de sus providencias, el tutelante tendr\u00e1 la opci\u00f3n de (i) acudir a la regla \u00a0 fijada en el Auto 04 del 3 de febrero de 2004, es decir, presentar la acci\u00f3n de \u00a0 tutela ante cualquier juez (unipersonal o colegiado) o incluso ante una \u00a0 corporaci\u00f3n judicial de la misma jerarqu\u00eda de la Corte Suprema de Justicia; o \u00a0 (ii) solicitar ante la Secretar\u00eda General de la Corte Constitucional, que \u00a0 radique para selecci\u00f3n la decisi\u00f3n proferida por la Corte Suprema de Justicia en \u00a0 la cual se concluy\u00f3 que la acci\u00f3n de tutela era absolutamente improcedente, con \u00a0 el fin de que surta el tr\u00e1mite fijado en las normas correspondientes al proceso \u00a0 de selecci\u00f3n. Para este efecto, el interesado adjuntar\u00e1 a la acci\u00f3n de tutela, \u00a0 la providencia donde se plasm\u00f3 la decisi\u00f3n que la tutela era absolutamente \u00a0 improcedente, as\u00ed como la providencia objeto de la acci\u00f3n de tutela\u201d. \u00a0 \u00a0<\/p>\n<p>3.6. As\u00ed las cosas, si bien la Corte Constitucional, \u00a0 mediante el Auto 004 de 2004 puso a disposici\u00f3n de los accionantes otros caminos \u00a0 judiciales para tramitar sus acciones de tutela, se present\u00f3 una nueva forma de \u00a0 imposibilidad de acceso a la administraci\u00f3n de justicia cuando esas otras \u00a0 autoridades judiciales se negaron a dar tr\u00e1mite a esas acciones de tutela. De \u00a0 manera que teniendo en cuenta la finalidad de la medida inicialmente adoptada &#8211; \u00a0 dar plena garant\u00eda al ejercicio de la acci\u00f3n de tutela y con ello al (i) acceso \u00a0 a la administraci\u00f3n de justicia, y (ii) a la efectividad del derecho al debido \u00a0 proceso, la Corte Constitucional consider\u00f3 pertinente abrir un nuevo camino para \u00a0 responder a esta problem\u00e1tica judicial. Por tal motivo, mediante Auto 100 de \u00a0 2008, consider\u00f3 conveniente y necesario establecer un nuevo camino judicial para \u00a0 el efectivo ejercicio de la acci\u00f3n de tutela y fue as\u00ed como admiti\u00f3 que fuese \u00a0 presentada de manera directa ante la Secretar\u00eda General de la Corte \u00a0 Constitucional para que surtiese el tr\u00e1mite de la selecci\u00f3n. Con esta nueva \u00a0 medida, se aseguraba el ejercicio de la acci\u00f3n de tutela y de paso se \u00a0 garantizaba el acceso a la administraci\u00f3n de justicia. \u00a0 \u00a0<\/p>\n<p>En este escenario y teniendo en cuenta las opciones \u00a0 contempladas en el citado Auto 100 de 2008, esta Corporaci\u00f3n se pronunci\u00f3 en \u00a0 varias oportunidades dentro de acciones de tutela presentadas como consecuencia \u00a0 de la falta de tr\u00e1mite por parte de la Sala de Casaci\u00f3n Civil de la Corte \u00a0 Suprema de Justicia. En las sentencias T-1094 de 2008,[21] \u00a0T-633 de 2009,[22] \u00a0T-013 de 2011,[23] \u00a0T-859 de 2011,[24] \u00a0T-214 de 2012,[25] \u00a0T-1038 de 2012,[26] \u00a0T-1095 de 2012,[27] \u00a0T-062 de 2013,[28] \u00a0SU-131 de 2013,[29] \u00a0T-255 de 2013,[30] \u00a0T-362 de 2013,[31] \u00a0T-450 de 2013,[32] \u00a0T-265 de 2014[33] \u00a0y SU-873 de 2014,[34] \u00a0los accionantes acudieron directamente ante este Tribunal y obtuvieron \u00a0 pronunciamientos de fondo frente a las solicitudes de amparo. En las sentencias \u00a0 T-754 de 2010,[35] \u00a0T-978 de 2011,[36] \u00a0T-357 de 2011,[37] \u00a0T-183 de 2012,[38] \u00a0SU-158 de 2013,[39] \u00a0T-445 de 2013,[40] \u00a0los accionantes presentaron las demandas ante el Consejo Superior de la \u00a0 Judicatura y luego de agotadas las instancias correspondientes, la Corporaci\u00f3n \u00a0 se pronunci\u00f3 sobre la decisi\u00f3n de los jueces de instancia. \u00a0 \u00a0<\/p>\n<p>3.7. En esta medida, cuando alguna Sala de Casaci\u00f3n de \u00a0 la Corte Suprema de Justicia no admita o d\u00e9 tr\u00e1mite a una acci\u00f3n de tutela \u00a0 presentada en contra de fallos proferidos por esa misma entidad, los ciudadanos, \u00a0 invocando el Auto 100, tendr\u00e1n la posibilidad (i) de presentar nuevamente la \u00a0 acci\u00f3n de tutela ante cualquier Juez de la Rep\u00fablica (unipersonal o colegiado) e \u00a0 incluso ante cualquier otra entidad de la misma jerarqu\u00eda de la Corte Suprema o \u00a0 (ii) presentarla directamente ante la Secretar\u00eda General de la Corte \u00a0 Constitucional para que \u00e9sta la env\u00ede a la Sala de Selecci\u00f3n respectiva y se le \u00a0 d\u00e9 tr\u00e1mite a la misma.[41] \u00a0Situaci\u00f3n que se present\u00f3 en el caso objeto de estudio, por tanto a este Alto \u00a0 Tribunal le corresponde adoptar una decisi\u00f3n de fondo. \u00a0 \u00a0<\/p>\n<p>4.\u00a0 Procedencia excepcional de la acci\u00f3n de \u00a0 tutela contra providencias judiciales. Reiteraci\u00f3n de jurisprudencia \u00a0 \u00a0<\/p>\n<p>La \u00a0 Constituci\u00f3n Pol\u00edtica en su art\u00edculo 86 indica expresamente que la acci\u00f3n de \u00a0 tutela procede\u00a0cuando los derechos constitucionales fundamentales se vean \u00a0 vulnerados o amenazados \u201cpor la acci\u00f3n o la omisi\u00f3n de cualquier autoridad p\u00fablica\u201d. \u00a0 No obstante, la Corte Constitucional ha \u00a0 admitido excepcionalmente la procedencia de la acci\u00f3n de tutela contra \u00a0 providencias judiciales que quebranten los derechos fundamentales de las partes \u00a0 y que se apartan notablemente de los mandatos constitucionales. Lo anterior, en \u00a0 atenci\u00f3n a los principios de cosa juzgada, autonom\u00eda e independencia judicial, \u00a0 seguridad jur\u00eddica, y a la naturaleza subsidiaria de la acci\u00f3n de tutela. \u00a0 \u00a0<\/p>\n<p>Debido a dichas situaciones excepcional\u00edsimas en un principio esta Corte \u00a0 desarroll\u00f3 la teor\u00eda de que la tutela era procedente contra providencias \u00a0 judiciales s\u00f3lo cuando las mismas constituyeran manifiestas v\u00edas de hecho,[42] es \u00a0 decir, decisiones ostensiblemente arbitrarias, por ejemplo, (i) se basan en \u00a0 normas evidentemente inaplicables (defecto sustantivo), (ii) son proferidas con \u00a0 carencia absoluta de competencia (defecto org\u00e1nico), (iii) se basan en una \u00a0 valoraci\u00f3n arbitraria de las pruebas (defecto f\u00e1ctico), o (iv) fueron proferidas \u00a0 en un tr\u00e1mite que se apart\u00f3 ostensiblemente del procedimiento fijado por la \u00a0 normativa vigente (defecto procedimental). Con el paso del tiempo, el Alto \u00a0 Tribunal en su jurisprudencia fue identificando otros defectos constitutivos de \u00a0 las llamadas v\u00edas de hecho. \u00a0 \u00a0<\/p>\n<p>Posteriormente, en el a\u00f1o 2005, este Alto Tribunal mediante Sentencia C-590 de \u00a0 dicha anualidad modific\u00f3 la doctrina de las v\u00edas de hecho. En esta medida \u00a0 precis\u00f3 y diferenci\u00f3 dos tipos de requisitos de procedencia de la acci\u00f3n de \u00a0 tutela contra providencias judiciales:[43] \u00a0unos requisitos generales de procedencia de naturaleza estrictamente procesal, y \u00a0 unas causales espec\u00edficas de procedibilidad de naturaleza sustantiva que recogen \u00a0 los defectos que antes eran denominados v\u00edas de hecho. \u00a0 \u00a0<\/p>\n<p>4.1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0Requisitos \u00a0 generales de procedencia excepcional de la acci\u00f3n de tutela contra providencias \u00a0 judiciales. \u00a0 \u00a0<\/p>\n<p>Los \u00a0 requisitos generales de procedencia se\u00f1alados en la sentencia C-590 de 2005, se \u00a0 definen como condiciones de procedimiento que buscan hacer compatible la \u00a0 procedencia de la acci\u00f3n de tutela contra providencias judiciales, con la \u00a0 eficacia de principios de estirpe constitucional y legal como la seguridad \u00a0 jur\u00eddica, la cosa juzgada, la independencia y autonom\u00eda del juez, y la \u00a0 distribuci\u00f3n jer\u00e1rquica de competencias al interior de la rama judicial.[44] Estos \u00a0 requisitos son los siguientes: \u00a0 \u00a0<\/p>\n<p>\u201ca. Que la cuesti\u00f3n que se discuta resulte \u00a0 de evidente relevancia constitucional. Como ya se mencion\u00f3, el juez \u00a0 constitucional no puede entrar a estudiar cuestiones que no tienen una clara y \u00a0 marcada importancia constitucional so pena de involucrarse en asuntos que \u00a0 corresponde definir a otras jurisdicciones[45]. En consecuencia, el \u00a0 juez de tutela debe indicar con toda claridad y de forma expresa porqu\u00e9 la \u00a0 cuesti\u00f3n que entra a resolver es genuinamente una cuesti\u00f3n de relevancia \u00a0 constitucional que afecta los derechos fundamentales de las partes. \u00a0 \u00a0<\/p>\n<p>b. Que se hayan agotado todos los medios\u00a0 \u00a0 -ordinarios y extraordinarios-\u00a0 de defensa judicial al alcance de la \u00a0 persona afectada, salvo que se trate de evitar la consumaci\u00f3n de un perjuicio \u00a0 iusfundamental irremediable[46].\u00a0 \u00a0 De all\u00ed que sea un deber del actor desplegar todos los mecanismos judiciales \u00a0 ordinarios que el sistema jur\u00eddico le otorga para la defensa de sus derechos.\u00a0 \u00a0 De no ser as\u00ed, esto es, de asumirse la acci\u00f3n de tutela como un mecanismo de \u00a0 protecci\u00f3n alternativo, se correr\u00eda el riesgo de vaciar las competencias de las \u00a0 distintas autoridades judiciales, de concentrar en la jurisdicci\u00f3n \u00a0 constitucional todas las decisiones inherentes a ellas y de propiciar un \u00a0 desborde institucional en el cumplimiento de las funciones de esta \u00faltima. \u00a0 \u00a0<\/p>\n<p>c. Que se cumpla el requisito de la \u00a0 inmediatez, es decir, que la tutela se hubiere interpuesto en un t\u00e9rmino \u00a0 razonable y proporcionado a partir del hecho que origin\u00f3 la vulneraci\u00f3n[47].\u00a0 \u00a0 De lo contrario, esto es, de permitir que la acci\u00f3n de tutela proceda meses o \u00a0 a\u00fan a\u00f1os despu\u00e9s de proferida la decisi\u00f3n, se sacrificar\u00edan los principios de \u00a0 cosa juzgada y seguridad jur\u00eddica ya que sobre todas las decisiones judiciales \u00a0 se cernir\u00eda una absoluta incertidumbre que las desdibujar\u00eda como mecanismos \u00a0 institucionales leg\u00edtimos de resoluci\u00f3n de conflictos. \u00a0 \u00a0<\/p>\n<p>d. Cuando se trate de una\u00a0 \u00a0 irregularidad procesal, debe quedar claro que la misma tiene un efecto decisivo \u00a0 o determinante en la sentencia que se impugna y que afecta los derechos \u00a0 fundamentales de la parte actora[48].\u00a0 \u00a0 No obstante, de acuerdo con la doctrina fijada en la Sentencia C-591-05, si la \u00a0 irregularidad comporta una grave lesi\u00f3n de derechos fundamentales, tal como \u00a0 ocurre con los casos de pruebas il\u00edcitas susceptibles de imputarse como cr\u00edmenes \u00a0 de lesa humanidad, la protecci\u00f3n de tales derechos se genera independientemente \u00a0 de la incidencia que tengan en el litigio y por ello hay lugar a la anulaci\u00f3n \u00a0 del juicio. \u00a0 \u00a0<\/p>\n<p>e. Que la parte actora identifique de manera \u00a0 razonable tanto los hechos que generaron la vulneraci\u00f3n como los derechos \u00a0 vulnerados y que hubiere alegado tal vulneraci\u00f3n en el proceso judicial siempre \u00a0 que esto hubiere sido posible[49].\u00a0 Esta exigencia \u00a0 es comprensible pues, sin que la acci\u00f3n de tutela llegue a rodearse de unas \u00a0 exigencias formales contrarias a su naturaleza y no previstas por el \u00a0 constituyente, s\u00ed es menester que el actor tenga claridad en cuanto al \u00a0 fundamento de la afectaci\u00f3n de derechos que imputa a la decisi\u00f3n judicial, que \u00a0 la haya planteado al interior del proceso y que d\u00e9 cuenta de todo ello al \u00a0 momento de pretender la protecci\u00f3n constitucional de sus derechos. \u00a0 \u00a0<\/p>\n<p>En la sentencia referida \u00a0 anteriormente se estableci\u00f3 que despu\u00e9s de probar el cumplimiento de los \u00a0 requisitos generales se\u00f1alados, el accionante debe demostrar que tuvo lugar \u00a0 alguna de las causales espec\u00edficas de procedibilidad o vicios en que pudo \u00a0 incurrir la autoridad judicial al proferir la decisi\u00f3n cuestionada.\u00a0Esas \u00a0 causales se examinan a continuaci\u00f3n: \u00a0 \u00a0<\/p>\n<p>4.2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Causales especiales de procedibilidad excepcional de la \u00a0 acci\u00f3n de tutela contra providencias judiciales \u00a0 \u00a0<\/p>\n<p>En \u00a0 la sentencia C-590 de 2005, despu\u00e9s de modificar la jurisprudencia sobre las \u00a0 v\u00edas de hecho, la Corte Constitucional precis\u00f3 las siguientes causales de \u00a0 procedibilidad de la acci\u00f3n de tutela contra providencias judiciales. Las cuales \u00a0 defini\u00f3 como defectos sustanciales que\u00a0 por su gravedad hacen incompatible \u00a0 la decisi\u00f3n judicial de los preceptos constitucionales[52].Estos son: \u00a0 \u00a0<\/p>\n<p>\u201ca. \u00a0 Defecto org\u00e1nico, que se presenta cuando el funcionario judicial que profiri\u00f3 la \u00a0 providencia impugnada, carece, absolutamente, de competencia para ello. \u00a0 \u00a0<\/p>\n<p>b. Defecto procedimental absoluto, que se \u00a0 origina cuando el juez actu\u00f3 completamente al margen del procedimiento \u00a0 establecido. \u00a0 \u00a0<\/p>\n<p>c.\u00a0 Defecto f\u00e1ctico, que surge cuando \u00a0 el juez carece del apoyo probatorio que permita la aplicaci\u00f3n del supuesto legal \u00a0 en el que se sustenta la decisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>d. Defecto material o sustantivo, como son \u00a0 los casos en que se decide con base en normas inexistentes o inconstitucionales[53] \u00a0o que presentan una evidente y grosera contradicci\u00f3n entre los fundamentos y la \u00a0 decisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>f. Error inducido, que se presenta cuando el \u00a0 juez o tribunal fue v\u00edctima de un enga\u00f1o por parte de terceros y ese enga\u00f1o lo \u00a0 condujo a la toma de una decisi\u00f3n que afecta derechos fundamentales. \u00a0 \u00a0<\/p>\n<p>g. Decisi\u00f3n sin motivaci\u00f3n, que implica el \u00a0 incumplimiento de los servidores judiciales de dar cuenta de los fundamentos \u00a0 f\u00e1cticos y jur\u00eddicos de sus decisiones en el entendido que precisamente en esa \u00a0 motivaci\u00f3n reposa la legitimidad de su \u00f3rbita funcional. \u00a0 \u00a0<\/p>\n<p>h. Desconocimiento del precedente, hip\u00f3tesis \u00a0 que se presenta, por ejemplo, \u00a0 cuando la Corte Constitucional establece el alcance de un derecho fundamental y \u00a0 el juez ordinario aplica una ley limitando sustancialmente dicho alcance. En \u00a0 estos casos la tutela procede como mecanismo para garantizar la eficacia \u00a0 jur\u00eddica del contenido constitucionalmente vinculante del derecho fundamental \u00a0 vulnerado\u201d[54]. \u00a0 \u00a0<\/p>\n<p>\u201ci. Violaci\u00f3n directa de la Constituci\u00f3n, que es \u00a0 el defecto que se deduce de \u00a0 infringir directamente una o varias disposiciones o normas razonablemente \u00a0 vinculables a la Constituci\u00f3n\u201d[55]. \u00a0 \u00a0<\/p>\n<p>Teniendo en cuenta que para la Sala resulta relevante analizar a \u00a0 fondo el defecto de violaci\u00f3n directa de la Constituci\u00f3n, debido a que a juicio \u00a0 de la tutelante el Alto Tribunal accionado tom\u00f3 una decisi\u00f3n con base en un \u00a0 requisito que hab\u00eda sido declarado inconstitucional por la Corte Constitucional \u00a0 mediante Sentencia C-428 de 2009, se proceder\u00e1 a hacer una breve caracterizaci\u00f3n \u00a0 de dicho defecto como causal espec\u00edfica de procedibilidad de la acci\u00f3n de tutela \u00a0 contra providencias judiciales. \u00a0 \u00a0<\/p>\n<p>4.3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0Violaci\u00f3n directa de la Constituci\u00f3n como \u00a0 causal espec\u00edfica de procedibilidad de la tutela contra providencias judiciales. \u00a0 Reiteraci\u00f3n de Jurisprudencia. \u00a0 \u00a0 \u00a0<\/p>\n<p>Todas las \u00a0 causales espec\u00edficas de procedencia de la acci\u00f3n de tutela contra providencias \u00a0 judiciales conllevan en s\u00ed mismas un quebrantamiento de la Carta Fundamental; \u00a0 sin embargo, esta Corte estableci\u00f3 una causal denominada violaci\u00f3n directa de la \u00a0 Constituci\u00f3n, originada en la obligaci\u00f3n que le asiste a todas las autoridades \u00a0 judiciales de velar por el cumplimiento del mandato consagrado en el art\u00edculo 4\u00b0 \u00a0 de la Carta Pol\u00edtica, seg\u00fan el cual \u201cla Constituci\u00f3n es norma de normas\u201d. \u00a0 De manera que en caso de incompatibilidad entre la Constituci\u00f3n y la ley u otra \u00a0 norma jur\u00eddica, se aplicar\u00e1n las disposiciones constitucionales. \u00a0 \u00a0<\/p>\n<p>En un principio, \u00a0 esta causal se concibi\u00f3 como un defecto sustantivo.[56] Posteriormente, \u00a0 en la Sentencia T-949 de 2003[57] \u00a0se determin\u00f3 como una causal espec\u00edfica de procedibilidad de la acci\u00f3n de tutela \u00a0 de car\u00e1cter independiente y aut\u00f3nomo,[58] \u00a0interpretaci\u00f3n que se consolid\u00f3 en la Sentencia C-590 de 2005[59] ya citada, en la \u00a0 que la este Tribunal incluy\u00f3 la violaci\u00f3n directa de la Constituci\u00f3n como un \u00a0 defecto aut\u00f3nomo que justifica la procedencia de la tutela contra providencias \u00a0 judiciales, dado que \u201c(\u2026) la violaci\u00f3n directa de la Constituci\u00f3n opera en \u00a0 dos circunstancias: uno (i), cuando se deja de aplicar una \u00a0 disposici\u00f3n ius fundamental a un caso concreto, dos (ii), al aplicar la ley al \u00a0 margen de los dictados de la Constituci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>En ese contexto, \u00a0 la jurisprudencia constitucional ha sostenido que acci\u00f3n de tutela contra \u00a0 providencias judiciales procede por violaci\u00f3n directa de la Constituci\u00f3n, \u00a0 cuando: \u00a0 \u00a0<\/p>\n<p>\u201c(a) \u00a0 en la soluci\u00f3n del caso se dej\u00f3 de interpretar y aplicar una disposici\u00f3n legal \u00a0 de conformidad con el precedente constitucional, (b) se trata de un derecho \u00a0 fundamental de aplicaci\u00f3n inmediata y (c) el juez en sus resoluciones vulner\u00f3 \u00a0 derechos fundamentales y no tuvo en cuenta el principio de interpretaci\u00f3n \u00a0 conforme con la Constituci\u00f3n.\u00a0 En el segundo caso, el juez debe tener en \u00a0 cuenta en sus fallos, que con base en el art\u00edculo 4 de la C.P, la Constituci\u00f3n \u00a0 es norma de normas y que en todo caso en que encuentre, deduzca o se le \u00a0 interpele sobre una norma que es incompatible con la Constituci\u00f3n, debe aplicar \u00a0 las disposiciones constitucionales con preferencia a las legales mediante el \u00a0 ejercicio de la excepci\u00f3n de inconstitucionalidad\u201d.[60] \u00a0 \u00a0<\/p>\n<p>As\u00ed las cosas, en \u00a0 virtud del actual modelo de ordenamiento constitucional \u201creconoce valor \u00a0 normativo superior a los preceptos constitucionales, y ellos contienen mandatos \u00a0 y previsiones de aplicaci\u00f3n directa por las distintas autoridades y, en \u00a0 determinados eventos, por los particulares\u201d,[61] la decisi\u00f3n \u00a0 judicial que desconozca o aplique indebida e irrazonablemente tales postulados, \u00a0 puede ser cuestionada en sede de tutela, en la medida que los jueces, en \u00a0 ejercicio de sus funciones, est\u00e1n sujetos a las disposiciones consagradas en la \u00a0 Constituci\u00f3n. En estos casos, la prevalencia del orden superior debe asegurarse \u00a0 aun cuando las partes no hubieren solicitado la inaplicaci\u00f3n de la norma para el \u00a0 caso particular. \u00a0 \u00a0<\/p>\n<p>5.\u00a0 \u00a0 Requisitos para acceder a la pensi\u00f3n de invalidez. Reiteraci\u00f3n de \u00a0 Jurisprudencia. \u00a0 \u00a0<\/p>\n<p>La Ley 100 de 1993, en su art\u00edculo 10 \u00a0 se\u00f1ala que el sistema general de pensiones tiene por objeto garantizar a la \u00a0 poblaci\u00f3n una protecci\u00f3n contra las contingencias derivadas de la vejez, \u00a0 invalidez y la muerte. Lo anterior, mediante el reconocimiento de las \u00a0 respectivas pensiones.[62] \u00a0 \u00a0<\/p>\n<p>La pensi\u00f3n de invalidez se define como \u00a0 aquella prestaci\u00f3n econ\u00f3mica que se otorga a una persona que, por enfermedad com\u00fan o profesional o por \u00a0 haber padecido un accidente, ha perdido la capacidad de locomoci\u00f3n y la plenitud \u00a0 de las funciones s\u00edquicas y f\u00edsicas y, como consecuencia, ha sufrido una p\u00e9rdida \u00a0 en su capacidad laboral que le impide llevar una vida cotidiana y social normal.[63] \u00a0 \u00a0<\/p>\n<p>El art\u00edculo 38 de la misma Ley 100 \u00a0 sostiene que para efecto del \u00a0 reconocimiento de la pensi\u00f3n de invalidez, la persona tiene que acreditar una \u00a0 p\u00e9rdida de capacidad laboral del 50% o m\u00e1s, de conformidad con el dictamen que \u00a0 emite una Junta Regional o una Junta Nacional, dependiendo del caso en concreto.[64] \u00a0Aunado a lo anterior, el art\u00edculo 39 de la ley en menci\u00f3n a\u00f1adi\u00f3 dos requisitos \u00a0 adicionales: \u00a0 \u00a0<\/p>\n<p>\u201ca. Que el afiliado se encuentre cotizando \u00a0 al r\u00e9gimen y hubiere cotizado por lo menos veintis\u00e9is (26) semanas, al momento \u00a0 de producirse el estado de invalidez. \u00a0 \u00a0<\/p>\n<p>b. Que habiendo dejado de cotizar al \u00a0 sistema, hubiere efectuado aportes durante por lo menos veintis\u00e9is (26) semanas \u00a0 del a\u00f1o inmediatamente anterior al momento en que se produzca el estado de \u00a0 invalidez\u201d. \u00a0 \u00a0<\/p>\n<p>Esta \u00faltima disposici\u00f3n fue modificada por la Ley 860 de 2003[65], \u00a0 la cual en su art\u00edculo 1\u00b0 estableci\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cTendr\u00e1 derecho a la pensi\u00f3n de invalidez \u00a0 el afiliado al sistema que conforme a lo dispuesto en el art\u00edculo anterior sea \u00a0 declarado inv\u00e1lido y acredite las siguientes condiciones: \u00a0 \u00a0<\/p>\n<p>1. Invalidez causada por enfermedad: Que \u00a0 haya cotizado cincuenta (50) semanas dentro de los \u00faltimos tres (3) a\u00f1os \u00a0 inmediatamente anteriores a la fecha de estructuraci\u00f3n y su fidelidad de \u00a0 cotizaci\u00f3n para con el sistema sea al menos del veinte por ciento (20%) del \u00a0 tiempo transcurrido entre el momento en que cumpli\u00f3 veinte (20) a\u00f1os de edad y \u00a0 la fecha de la primera calificaci\u00f3n del estado de invalidez. \u00a0 \u00a0<\/p>\n<p>2. Invalidez causada por accidente: Que \u00a0 haya cotizado cincuenta (50) semanas dentro de los \u00faltimos tres (3) a\u00f1os \u00a0 inmediatamente anteriores al hecho causante de la misma, y su fidelidad de \u00a0 cotizaci\u00f3n para con el sistema sea al menos del veinte por ciento (20%) del \u00a0 tiempo transcurrido entre el momento en que cumpli\u00f3 veinte (20) a\u00f1os de edad y \u00a0 la fecha de la primera calificaci\u00f3n del estado de invalidez. \u00a0 \u00a0<\/p>\n<p>PAR\u00c1GRAFO 1\u00b0 Los menores de veinte (20) \u00a0 a\u00f1os de edad s\u00f3lo deber\u00e1n acreditar que han cotizado veintis\u00e9is (26) semanas en \u00a0 el \u00faltimo a\u00f1o inmediatamente anterior al hecho causante de su invalidez o su \u00a0 declaratoria. \u00a0 \u00a0<\/p>\n<p>PAR\u00c1GRAFO 2\u00b0 Cuando el afiliado haya \u00a0 cotizado por lo menos el 75% de las semanas m\u00ednimas requeridas para acceder a la \u00a0 pensi\u00f3n de vejez, s\u00f3lo se requerir\u00e1 que haya cotizado 25 semanas en los \u00faltimos \u00a0 tres (3) a\u00f1os.\u201d \u00a0 \u00a0<\/p>\n<p>Con este cambio normativo se dispuso la implementaci\u00f3n de unos \u00a0 requisitos m\u00e1s rigurosos, al aumentar el n\u00famero de semanas de 26 a 50 dentro de \u00a0 los \u00faltimos tres a\u00f1os inmediatamente anteriores a la fecha de estructuraci\u00f3n y \u00a0 se agreg\u00f3 el requisito de fidelidad al sistema. \u00a0 \u00a0<\/p>\n<p>Al analizar la constitucionalidad de este \u00a0 art\u00edculo, la Corte a trav\u00e9s de la Sentencia C-428 de 2009[66], declar\u00f3 inexequible el requisito de \u00a0 fidelidad al sistema introducido por la Ley 860 de 2003, por ser regresivo y \u00a0 resultar m\u00e1s gravoso al hacer a\u00fan m\u00e1s riguroso el acceso a la pensi\u00f3n de \u00a0 invalidez. Al respecto \u00a0 indic\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cCon \u00a0 las modificaciones introducidas en los numerales 1\u00ba y 2\u00ba del art\u00edculo 1\u00ba de\u00a0 \u00a0 la Ley 860 de 2003, el Legislador agreg\u00f3 un requisito de acceso al beneficio \u00a0 pensional m\u00e1s gravoso para el cotizante, el requisito de fidelidad al sistema \u00a0 que no estaba prevista en la Ley 100 de 1993, y aparece, prima facie, como una \u00a0 medida regresiva en materia de seguridad social al hacer m\u00e1s riguroso el acceso \u00a0 a la pensi\u00f3n de invalidez, y no habiendo poblaci\u00f3n beneficiada por la norma como \u00a0 en el requisito de las semanas m\u00ednimas de cotizaci\u00f3n, ni advirtiendo una \u00a0 conexi\u00f3n entre el fin previsto en la norma -la promoci\u00f3n de la cultura de la \u00a0 afiliaci\u00f3n a la seguridad social y el control de los fraudes- con los efectos \u00a0 producidos por la misma, este requisito de fidelidad no logra desvirtuar la \u00a0 presunci\u00f3n de regresividad, a diferencia del caso respecto del cual la reforma \u00a0 mostr\u00f3 matices de progresividad a pesar del aumento en el n\u00famero de semanas \u00a0 requeridas. Se concluye que a pesar de poder tener un fin constitucional \u00a0 leg\u00edtimo, en tanto busca asegurar la estabilidad financiera del sistema \u00a0 pensional mediante la cultura de afiliaci\u00f3n y disminuci\u00f3n del fraude, la norma \u00a0 no es conducente para la realizaci\u00f3n de dichos fines al imponer una carga mayor \u00a0 a las personas a quienes no se les hab\u00eda exigido fidelidad -los afiliados de la \u00a0 tercera edad. En consecuencia, el costo social que apareja la modificaci\u00f3n \u00a0 introducida por el requisito de fidelidad incluido en el art\u00edculo 1 de la Ley \u00a0 860 de 2003 es mayor que beneficio que reportar\u00eda para la colectividad\u201d. \u00a0 \u00a0<\/p>\n<p>Esta declaratoria de inexequibilidad y \u00a0 evidente regresividad ha sido reiterada por la Corte Constitucional en \u00a0 pronunciamientos posteriores,[67] en los cuales se ha manifestado que la norma era \u00a0 inconstitucional desde sus inicios, motivo por el cual no pod\u00eda producir \u00a0 efectos. De esta manera, se ha entendido que a aquellas situaciones jur\u00eddicas \u00a0 que se generaron antes de la inexequibilidad del art\u00edculo 1 de la Ley 860 de \u00a0 2003 tampoco se les puede exigir el requisito de fidelidad mencionado. Al \u00a0 respecto, en Sentencia T- 826 de 2014[68] se recogieron dichos pronunciamientos y \u00a0 se precis\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cLa sentencia C-428 de 2009 que declar\u00f3 la \u00a0 inexequibilidad del requisito de fidelidad, no hizo nada diferente a ratificar \u00a0 \u2018una situaci\u00f3n que desde siempre fue contraria al derecho fundamental a la \u00a0 seguridad social en pensiones\u2019. Por consiguiente, el pronunciamiento hecho tuvo \u00a0 un car\u00e1cter declarativo y no constitutivo. \u00a0 \u00a0<\/p>\n<p>18.\u00a0\u00a0\u00a0\u00a0\u00a0 En este \u00a0 punto, vale la pena precisar qu\u00e9 pasa con las solicitudes de reconocimiento de \u00a0 pensi\u00f3n presentadas antes de la sentencia que declar\u00f3 la inexequibilidad de la \u00a0 norma. \u00a0 \u00a0<\/p>\n<p>Para dar soluci\u00f3n a ello, se debe tener a \u00a0 consideraci\u00f3n la fuerza y el car\u00e1cter vinculante de las sentencias, cuya ratio \u00a0 decidendi constituye en precedente constitucional, el cual debe observarse para \u00a0 atender casos similares.\u00a0 \u00a0 \u00a0<\/p>\n<p>As\u00ed mismo, y como se mencion\u00f3 previamente, \u00a0 la declaratoria de inexequibilidad de dicha disposici\u00f3n, lo \u00fanico que hizo fue \u00a0 ratificar una situaci\u00f3n que desde un principio era inconstitucional, por lo que \u00a0 la disposici\u00f3n enjuiciada no pod\u00eda irradiar los efectos que pretendi\u00f3. \u00a0 \u00a0<\/p>\n<p>De esta manera, a las situaciones \u00a0 jur\u00eddicas que se generaron previo a la declaratoria de inexequibilidad de la \u00a0 norma, tampoco se les puede exigir el requisito de fidelidad mencionado. \u00a0 \u00a0<\/p>\n<p>19.\u00a0\u00a0\u00a0\u00a0\u00a0 La \u00a0 mentada situaci\u00f3n, ha sido estudiada en reiteradas oportunidades por esta \u00a0 corporaci\u00f3n, como en los fallos T-266 de 2010, T-532 de 2010, T-615 de 2010, \u00a0 T-016 de 2011 y T-453 de 2011 entre muchos otros, dentro de los cuales se ha \u00a0 dicho de manera un\u00edvoca, que la exigencia del requisito de fidelidad de la Ley \u00a0 860 de 2003, deviene en inadmisible sin importar la fecha de estructuraci\u00f3n de \u00a0 la enfermedad, pues\u00a0 la sentencia C-428 de 2009, lo que hizo fue corregir \u00a0 una situaci\u00f3n que desde siempre fue inconstitucional, por lo que dicha \u00a0 providencia ten\u00eda efecto declarativo y no constitutivo, generando con ello que \u00a0 las entidades prestadores de este servicio no se excusen en que el hecho \u00a0 generador del derecho pensional sea anterior a esos fallos de \u00a0 constitucionalidad, pues el car\u00e1cter vinculante de la ratio decidendi se los \u00a0 impide\u201d(subrayado fuera del texto). \u00a0 \u00a0<\/p>\n<p>Teniendo en cuenta lo anterior, \u00a0 actualmente se exigen dos requisitos para acceder a la pensi\u00f3n de invalidez (i) \u00a0 tener una p\u00e9rdida de capacidad laboral igual o superior al 50%, y (ii) haber cotizado como m\u00ednimo cincuenta (50) \u00a0 semanas en los tres (3) a\u00f1os inmediatamente anteriores a la fecha de \u00a0 estructuraci\u00f3n de la invalidez. \u00a0En esta medida, exigir el cumplimiento del \u00a0 requisito de fidelidad para acceder a reconocer y pagar una pensi\u00f3n de invalidez \u00a0 es inconstitucional, pues el mismo fue excluido del ordenamiento por la Corte \u00a0 Constitucional mediante Sentencia C-428 de 2009, al considerarse regresivo y \u00a0 gravoso para el solicitante, decisi\u00f3n que hizo tr\u00e1nsito a cosa juzgada y tiene \u00a0 efectos erga omnes, por tanto es de obligatorio cumplimiento.[69]\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>III. CASO CONCRETO \u00a0 \u00a0<\/p>\n<p>1. La acci\u00f3n de tutela presentada por Elizabeth Lenis \u00a0 Mora es procedente para \u00a0 atacar las providencias judiciales referenciadas \u00a0 \u00a0<\/p>\n<p>La Sala observa que en este asunto concurren los \u00a0 requisitos generales de procedibilidad mencionados, por lo que la acci\u00f3n de \u00a0 tutela presentada por Elizabeth Lenis Mora es apta para controvertir las \u00a0 sentencias proferidas por el Juzgado Quinto Laboral del Circuito de Cali y la \u00a0 Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia.\u00a0 \u00a0 \u00a0<\/p>\n<p>1.1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0El asunto \u00a0 debatido reviste relevancia constitucional. \u00a0 \u00a0<\/p>\n<p>1.2.\u00a0\u00a0\u00a0 \u00a0La tutela no \u00a0 se dirige contra una sentencia de tutela \u00a0 \u00a0<\/p>\n<p>Como se ha indicado, la presente acci\u00f3n de \u00a0 tutela se dirige contra las providencias proferidas por la Sala de Casaci\u00f3n \u00a0 Laboral de la Corte Suprema de Justicia y por el Juzgado 5 Laboral del Circuito \u00a0 de Cali, en el curso del proceso laboral que inici\u00f3 la accionante contra el \u00a0 Fondo de Pensiones y Cesant\u00edas PORVENIR S.A, a efectos \u00a0 de obtener el reconocimiento y pago de su pensi\u00f3n de invalidez por tener una \u00a0 p\u00e9rdida de capacidad laboral del 67.37%. \u00a0 \u00a0<\/p>\n<p>1.3.\u00a0\u00a0\u00a0 \u00a0Existi\u00f3 \u00a0 inmediatez entre los hechos y el ejercicio de la acci\u00f3n de tutela. \u00a0 \u00a0<\/p>\n<p>Teniendo en cuenta que la finalidad de la acci\u00f3n de \u00a0 tutela es brindar una protecci\u00f3n inmediata \u00a0 a los derechos amenazados o vulnerados, \u00e9sta debe presentarse en un t\u00e9rmino \u00a0 prudencial so pena de ser declarada improcedente. Lo anterior debido a que \u00a0 \u201cla acci\u00f3n de tutela ha sido instituida como remedio de aplicaci\u00f3n urgente que \u00a0 se hace preciso administrar en guarda de la efectividad concreta y actual del \u00a0 derecho objeto de violaci\u00f3n o amenaza\u201d.[70]\u00a0 \u00a0 La exigencia de este presupuesto, tal como lo ha manifestado esta Corporaci\u00f3n, \u00a0 no conlleva la existencia de un t\u00e9rmino de caducidad, tal y como lo afirm\u00f3 esta \u00a0 Corporaci\u00f3n[71] \u00a0en la medida que el art\u00edculo 86 Superior se\u00f1ala que puede intentarse en todo \u00a0 momento. No obstante, la Corte \u00a0 Constitucional ha sostenido, de manera reiterada y consistente, que la solicitud \u00a0 de amparo constitucional debe interponerse en un t\u00e9rmino oportuno, justo y \u00a0 razonable, dado que una de las caracter\u00edsticas esenciales de este mecanismo de \u00a0 protecci\u00f3n es el principio de inmediatez.[72] Corresponder\u00e1 entonces, a \u00a0 la autoridad judicial el an\u00e1lisis en cada caso concreto del tiempo en el que se \u00a0 interpone la acci\u00f3n de tutela, pues no cualquier tardanza puede juzgarse como \u00a0 injustificada o irrazonable. \u00a0 \u00a0<\/p>\n<p>En ese contexto, la Corte ha desarrollado diferentes \u00a0 criterios para valorar la admisibilidad de una acci\u00f3n de tutela que se presenta \u00a0 luego de transcurrido un largo periodo de tiempo respecto del hecho generador de \u00a0 la vulneraci\u00f3n o amenaza de derechos: \u201c(i) [q]ue se demuestre que la \u00a0 vulneraci\u00f3n es permanente en el tiempo y que, pese a que el hecho que la origin\u00f3 \u00a0 por primera vez es muy antiguo respecto de la presentaci\u00f3n de la tutela, la \u00a0 situaci\u00f3n desfavorable del actor derivada del irrespeto por sus derechos, \u00a0 contin\u00faa y es actual. Y (ii) que la especial situaci\u00f3n de aquella persona a \u00a0 quien se le han vulnerado sus derechos fundamentales, convierte en \u00a0 desproporcionado el hecho de adjudicarle la carga de acudir a un juez; por \u00a0 ejemplo el estado de indefensi\u00f3n, interdicci\u00f3n, abandono, minor\u00eda de edad, \u00a0 incapacidad f\u00edsica, entre otros\u201d.[73] Estas circunstancias permiten que la exigencia del \u00a0 principio de inmediatez no se analice de manera estricta ya que, \u201cla acci\u00f3n \u00a0 de tutela tiene como objetivo la protecci\u00f3n cierta y efectiva de derechos \u00a0 fundamentales que se encuentran amenazados, bien por acci\u00f3n o bien, por omisi\u00f3n \u00a0 de autoridad p\u00fablica o particular cuando a ello hay lugar. Ese objetivo, no se \u00a0 agota con el simple paso del tiempo, sino que contin\u00faa vigente mientras el bien \u00a0 o inter\u00e9s que se pretende tutelar pueda seguir siendo tutelado para evitar que \u00a0 se consume un da\u00f1o antijur\u00eddico de forma irreparable\u201d.[74] \u00a0 \u00a0<\/p>\n<p>Ahora bien, aunque en este caso han transcurrido m\u00e1s de \u00a0 seis (6) a\u00f1os desde que se profiri\u00f3 la sentencia atacada,[75] la \u00a0 jurisprudencia de esta Corte de manera reiterada ha se\u00f1alado que el derecho a la \u00a0 pensi\u00f3n es imprescriptible, lo que permite afirmar que la vulneraci\u00f3n que se \u00a0 presenta respecto de este derecho de la tutelante es actual y ha perdurado \u00a0 durante estos a\u00f1os, puesto que la negativa de su pensi\u00f3n fue resuelta con base \u00a0 en un requisito que fue declarado inconstitucional por esta Corporaci\u00f3n desde \u00a0 sus inicios, por lo que no pod\u00eda producir efectos. Por tanto, tal y como se \u00a0 mencion\u00f3 en la parte considerativa de esta providencia, a aquellas situaciones \u00a0 jur\u00eddicas que se generaron antes de la inexequibilidad de dicha norma, tampoco \u00a0 se les puede exigir dicho requisito de fidelidad. \u00a0 \u00a0<\/p>\n<p>En la \u00a0 actualidad, la accionante no percibe su pensi\u00f3n de invalidez y eso le impide \u00a0 llevar una vida con contenidos m\u00ednimos de dignidad, pues a pesar de su \u00a0 discapacidad, debe trabajar de manera informal para poder sostener a sus hijos[76] \u00a0y solventar sus necesidades b\u00e1sicas. \u00a0 \u00a0<\/p>\n<p>Adicionalmente, para el an\u00e1lisis de \u00a0 inmediatez cabe tener en cuenta que, en este caso, la decisi\u00f3n de la Sala \u00a0 Laboral de la Corte Suprema de Justicia gener\u00f3 confusi\u00f3n en la accionante toda \u00a0 vez que, tal como lo se\u00f1ala, estuvo convencida de la imposibilidad de solicitar \u00a0 nuevamente su pensi\u00f3n al haber agotado la v\u00eda ordinaria y la acci\u00f3n de tutela \u00a0 que en ese momento fue infructuosa. Situaci\u00f3n que agrav\u00f3 su derecho de acceso a \u00a0 la administraci\u00f3n de justicia, especialmente la actuaci\u00f3n arbitraria de la Sala \u00a0 de Casaci\u00f3n Civil de la Corte Suprema de Justicia, la cual adem\u00e1s de declarar la \u00a0 nulidad del proceso de tutela, decidi\u00f3 no admitir para tr\u00e1mite la misma, \u00a0 desconociendo as\u00ed su deber de procurar el restablecimiento de los derechos \u00a0 afectados de los ciudadanos y el mandato de supremac\u00eda constitucional. \u00a0 \u00a0<\/p>\n<p>Finalmente y de conformidad con la \u00a0 respuesta a la petici\u00f3n radicada por la accionante el 30 de mayo de 2017 a la \u00a0 AFP Porvenir, debe considerarse que la posici\u00f3n del fondo de pensiones no ha \u00a0 variado y desconoce el precedente de esta Corporaci\u00f3n, al insistir en la \u00a0 exigencia del requisito de fidelidad para que la se\u00f1ora Lenis Mora acceda a su \u00a0 pensi\u00f3n de invalidez. \u00a0 \u00a0<\/p>\n<p>Por lo tanto, atendiendo las circunstancias \u00a0 particulares del caso objeto de estudio, la vulneraci\u00f3n del derecho de la \u00a0 accionante se mantiene en la actualidad, hecho que permite concluir que el \u00a0 requisito de inmediatez se encuentra superado. \u00a0 \u00a0<\/p>\n<p>1.4.\u00a0\u00a0\u00a0 \u00a0Agotamiento de todos los medios de defensa \u00a0 judicial. \u00a0 \u00a0<\/p>\n<p>Observa la Sala que dentro de los hechos narrados y de \u00a0 las pruebas aportadas en el expediente se demuestra que la tutelante ante la \u00a0 negativa de PORVENIR S.A de reconocer su pensi\u00f3n de invalidez inici\u00f3 proceso \u00a0 ordinario laboral e incluso dicho proceso lleg\u00f3 hasta casaci\u00f3n ante la Corte \u00a0 Suprema de Justicia, agotando as\u00ed los recursos procedentes en la jurisdicci\u00f3n \u00a0 ordinaria. \u00a0 \u00a0 \u00a0<\/p>\n<p>Posteriormente, al darse cuenta que la Corte Suprema le \u00a0 hab\u00eda negado en el a\u00f1o 2011, el reconocimiento y pago de su pensi\u00f3n de invalidez \u00a0 por no cumplir con el requisito de fidelidad al sistema,[77] \u00a0present\u00f3 acci\u00f3n de tutela. En primera instancia la Sala de Casaci\u00f3n Penal de la \u00a0 Corte Suprema de Justicia neg\u00f3 por improcedente la acci\u00f3n; en segunda instancia, \u00a0 la Sala de Casaci\u00f3n Civil de ese mismo Tribunal declar\u00f3 la nulidad de lo actuado \u00a0 desde el auto que orden\u00f3 el tr\u00e1mite de la acci\u00f3n por considerar que la admisi\u00f3n \u00a0 de la tutela implicar\u00eda desconocer la intangibilidad de las decisiones \u00a0 proferidas en sede de casaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Tiempo despu\u00e9s, en mayo de 2017, solicit\u00f3 \u00a0 una vez m\u00e1s el reconocimiento de su pensi\u00f3n, petici\u00f3n que fue negada por el \u00a0 fondo de pensiones por estimar que exist\u00eda cosa juzgada en su caso. Teniendo en \u00a0 cuenta lo anterior y que la autoridad judicial citada se abstuvo de estudiar de \u00a0 fondo el presente caso, en virtud del Auto 100 de 2008[78] la accionante \u00a0 procedi\u00f3 a presentar directamente el expediente ante la Secretar\u00eda General de \u00a0 esta Corporaci\u00f3n, para que se surtiera el tr\u00e1mite de selecci\u00f3n respectivo[79]. \u00a0 \u00a0<\/p>\n<p>De lo anterior, se puede observar que la \u00a0 actora cumpli\u00f3 con el requisito de agotar todos los medios de defensa judiciales \u00a0 a su alcance para obtener la pensi\u00f3n de invalidez a la que a su juicio, tiene \u00a0 derecho. \u00a0 \u00a0<\/p>\n<p>2.\u00a0 \u00a0Violaci\u00f3n directa \u00a0 de la Constituci\u00f3n por parte de las autoridades accionadas por aplicaci\u00f3n de una \u00a0 norma inconstitucional. \u00a0 \u00a0<\/p>\n<p>2.1. De \u00a0 conformidad con el problema jur\u00eddico planteado, le corresponde a esta Sala \u00a0 establecer si la Sala de Casaci\u00f3n Laboral demandada vulner\u00f3 el derecho \u00a0 fundamental al debido proceso de la accionante al dar aplicaci\u00f3n a una norma que \u00a0 fue declarada inexequible mediante sentencia C-428 de 2009.\u00a0 \u00a0 \u00a0<\/p>\n<p>Como se indic\u00f3 en \u00a0 precedencia, la configuraci\u00f3n de este defecto ocurre entre otros eventos, cuando \u00a0 el juez ordinario en la soluci\u00f3n del caso se dej\u00f3 de interpretar y aplicar una \u00a0 disposici\u00f3n legal de conformidad con el precedente constitucional, en perjuicio \u00a0 de los derechos fundamentales de los ciudadanos. \u00a0 \u00a0<\/p>\n<p>2.2. En el caso \u00a0 objeto de estudio, el Juzgado Quinto Laboral del Circuito de Cali en sentencia \u00a0 del treinta (30) de abril de dos mil nueve (2009) y la Sala Laboral de la Corte \u00a0 Suprema de Justicia, en providencia del veintid\u00f3s (22) de noviembre de dos mil \u00a0 once (2011), le negaron el reconocimiento de la pensi\u00f3n de invalidez a la se\u00f1ora \u00a0 Elizabeth Lenis Mora por no acreditar el requisito de fidelidad al sistema. \u00a0 \u00a0<\/p>\n<p>A juicio del juez \u00a0 laboral de primera instancia,[80] \u00a0no era posible acceder a las pretensiones de la accionante, aun a pesar de su \u201cpenosa \u00a0 enfermedad y ser persona de la tercera edad\u201d por cuanto no cumpl\u00eda los \u00a0 requisitos exigidos por las leyes que regulan la materia. Esta decisi\u00f3n fue \u00a0 revocada en segunda instancia por el Tribunal Superior de Cali,[81] autoridad que \u00a0 consider\u00f3 que frente al requisito de la fidelidad se\u00f1alado en el art. 1 de la \u00a0 Ley 860 de 2003 deb\u00eda aplicarse la excepci\u00f3n de inconstitucionalidad.\u00a0 Por \u00a0 su parte, la Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia[82] \u00a0cas\u00f3 la sentencia proferida por el citado Tribunal Superior, argumentando que la \u00a0 pretensi\u00f3n de reconocimiento pensional no prosperaba en la medida que el \u00a0 requisito de fidelidad estaba vigente para la fecha en la que se estructur\u00f3 su \u00a0 estado de invalidez, esto es, el 2 de agosto de 2006. En ese sentido, consider\u00f3 \u00a0 que \u201cal aplicar la excepci\u00f3n de inconstitucionalidad frente al requisito de \u00a0 fidelidad al sistema de pensiones cuando la invalidez de la actora se estructur\u00f3 \u00a0 el 2 de agosto de 2006, es decir, en el interregno entre la vigencia de la Ley \u00a0 860 de 2003 y el momento en que fue proferida la decisi\u00f3n de inexequibilidad, \u00a0 que no tuvo efectos hacia el pasado, el Tribunal desconoci\u00f3 que el par\u00e1grafo del \u00a0 art\u00edculo 20 de la Ley 393 de 1997 no da la posibilidad de echar mano de aquella \u00a0 figura cuando existe un previo pronunciamiento de exequibilidad por parte del \u00a0 \u00f3rgano encargado, esto es, la Corte Constitucional o el Consejo de Estado (\u2026)\u201d. \u00a0 \u00a0<\/p>\n<p>2.3. En materia \u00a0 de pensi\u00f3n de invalidez, desde la sentencia C-428 de 2009 que declar\u00f3 \u00a0 inexequible el art\u00edculo 1 de la Ley 860 de 2003, esta Corte ha sostenido que \u00a0 esta situaci\u00f3n cobija a aquellas prestaciones que se consolidaron antes de la \u00a0 decisi\u00f3n, de manera que no es posible exigir en esos eventos el requisito de \u00a0 fidelidad all\u00ed contemplado. En ese contexto, si una autoridad judicial niega el \u00a0 derecho a la pensi\u00f3n de invalidez bajo el argumento de no cumplir con el \u00a0 requisito de fidelidad, estar\u00eda incurriendo en un defecto por violaci\u00f3n directa \u00a0 de la Constituci\u00f3n, en la medida que desconoce el mandato de progresividad en \u00a0 materia de seguridad social en pensiones contemplada en los art\u00edculos 48 y 53 \u00a0 superiores, raz\u00f3n de la inexequibilidad del mencionado requisito de fidelidad, \u00a0 el cual, a juicio de esta Corporaci\u00f3n, impone una barrera adicional para el \u00a0 acceso a la prestaci\u00f3n por invalidez, que no se encuentra justificada en un \u00a0 Estado Social de Derecho. \u00a0 \u00a0<\/p>\n<p>2.4. Bajo este \u00a0 entendido, la providencia controvertida de la Sala de Casaci\u00f3n Laboral de la \u00a0 Corte Suprema de Justicia incurri\u00f3 en un defecto por violaci\u00f3n directa de la \u00a0 Carta Pol\u00edtica, en la medida que exigi\u00f3 a la accionante el requisito de \u00a0 fidelidad para acceder al reconocimiento de la pensi\u00f3n de invalidez, en \u00a0 desconocimiento del mandato superior de progresividad contenido en el art\u00edculo \u00a0 48 constitucional. De manera que exigirle a la se\u00f1ora Lenis Mora que acredite \u00a0 fidelidad al sistema para efectos de serle reconocida su pensi\u00f3n de invalidez, \u00a0 significa, por un lado, imponerle el cumplimiento de un presupuesto regresivo \u00a0 que no es aceptable en el marco constitucional actual y por el otro, otorgarle \u00a0 efectos jur\u00eddicos a una disposici\u00f3n declarada inconstitucional y cuya \u00a0 inexequibilidad cobija aquellas situaciones jur\u00eddicas consolidadas antes del \u00a0 pronunciamiento de esta Corte en el a\u00f1o 2009, en la medida que, como se indic\u00f3, \u00a0 este Tribunal lo que hizo fue corregir una situaci\u00f3n que desde siempre fue \u00a0 contraria a la Constituci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Vulneraci\u00f3n que \u00a0 ha sido perpetuada por el fondo administrador de pensiones, Porvenir S.A., al \u00a0 mantener la exigencia de un requisito que a la fecha no est\u00e1 vigente y que desde \u00a0 su inexequibilidad en 2009, de acuerdo con la jurisprudencia de esta \u00a0 Corporaci\u00f3n, est\u00e1 obligado a omitirlo en las solicitudes de reconocimiento de \u00a0 prestaciones sociales, incluso en aquellos casos, como el de la accionante, en \u00a0 los que la fecha de estructuraci\u00f3n de la invalidez se fij\u00f3 durante la vigencia \u00a0 de la norma. \u00a0 \u00a0<\/p>\n<p>Adem\u00e1s, la Sala \u00a0 no puede dejar de resaltar que esta exigencia le ha generado un grave perjuicio \u00a0 al m\u00ednimo vital de la peticionaria, pues la ausencia de la pensi\u00f3n de invalidez \u00a0 a la que tiene derecho la ha obligado a recurrir a trabajos informales para \u00a0 garantizar la subsistencia de su hogar,[83] \u00a0aun a pesar de sus dolencias y de su edad.\u00a0 \u00a0 \u00a0<\/p>\n<p>2.5. En este \u00a0 caso, verificado el expediente advierte esta Sala que la se\u00f1ora Elizabeth Lenis \u00a0 Mora cumple con los requisitos para acceder a la pensi\u00f3n de invalidez, esto es, \u00a0 (i) cuenta con una p\u00e9rdida de la capacidad laboral superior al 50% al ser \u00a0 calificada con un 67.37% y (ii) cotiz\u00f3 50 semanas dentro de los tres a\u00f1os \u00a0 inmediatamente anteriores al 2 de agosto de 2006, fecha de estructuraci\u00f3n de la \u00a0 invalidez, tal como se analiz\u00f3 en la sentencia del Tribunal Superior de Cali.[84] \u00a0Por lo que la negaci\u00f3n de acceso a esta prestaci\u00f3n, ha vulnerado su derecho a la \u00a0 seguridad social. \u00a0 \u00a0<\/p>\n<p>2.6. Finalmente, \u00a0 destaca esta Sala Plena que la actuaci\u00f3n de la Sala de Casaci\u00f3n Civil de la \u00a0 Corte Suprema de Justicia afect\u00f3 gravemente el derecho fundamental de acceso a \u00a0 la administraci\u00f3n de justicia de la se\u00f1ora Lenis Mora, al negarse a admitir la \u00a0 acci\u00f3n de tutela por ella instaurada, hecho que se constituy\u00f3 en un acto de \u00a0 denegaci\u00f3n de justicia e imposibilit\u00f3 el restablecimiento de los derechos \u00a0 fundamentales invocados en su demanda. Como se explic\u00f3 en el numeral tercero de \u00a0 las consideraciones de esta sentencia, las autoridades judiciales no pueden \u00a0 declarar la nulidad de los procesos de tutela argumentando que no procede la \u00a0 tutela contra decisiones de una alta corte, y en todo caso debe remitirse el \u00a0 expediente a la Corte Constitucional para que se surta el tr\u00e1mite de revisi\u00f3n. \u00a0 Esta actuaci\u00f3n resulta contraria a los derechos al acceso a la administraci\u00f3n de \u00a0 justicia, la existencia de un recurso judicial efectivo para la protecci\u00f3n de \u00a0 los derechos humanos, y al ejercicio de la acci\u00f3n de tutela, consagrados en los \u00a0 art\u00edculos 86 y 228 de la Constituci\u00f3n Pol\u00edtica y 25 de la Convenci\u00f3n Americana \u00a0 de Derechos Humanos. \u00a0 \u00a0<\/p>\n<p>2.7. Por estas \u00a0 razones, resulta inconstitucional la decisi\u00f3n de la Sala de Casaci\u00f3n Laboral de \u00a0 la Corte Suprema de Justicia al fundamentarse en la exigencia del requisito de \u00a0 fidelidad en el caso de la actora, bajo el entendimiento de que la fecha de \u00a0 estructuraci\u00f3n de la invalidez es anterior al retiro de ese presupuesto del \u00a0 ordenamiento jur\u00eddico. Tal como se indic\u00f3, era necesario que la autoridad \u00a0 judicial lo inaplicara con el fin de garantizar el mandato de progresividad en \u00a0 materia de seguridad social en pensiones y el principio constitucional de \u00a0 proporcionalidad. \u00a0 \u00a0<\/p>\n<p>En consecuencia, \u00a0 la Sala Plena amparar\u00e1 los derechos fundamentales al debido proceso, al acceso a \u00a0 la administraci\u00f3n de justicia, a la seguridad social y al m\u00ednimo vital de la \u00a0 accionante y dejar\u00e1 sin efecto la sentencia censurada, en tanto no accedi\u00f3 a las \u00a0 pretensiones de Elizabeth Lenis Mora porque no cumpl\u00eda el requisito de \u00a0 fidelidad. \u00a0 \u00a0<\/p>\n<p>IV. CONCLUSI\u00d3N \u00a0 \u00a0<\/p>\n<p>1. La Sala de Casaci\u00f3n Laboral de la Corte \u00a0 Suprema de Justicia vulner\u00f3 los derechos fundamentales al debido proceso, al \u00a0 acceso a la administraci\u00f3n de justicia, a la seguridad social y al m\u00ednimo vital \u00a0 de Elizabeth Lenis Mora, al negarle el reconocimiento de la pensi\u00f3n de invalidez \u00a0 bajo el argumento de no acreditar el requisito de fidelidad al sistema. Dicho \u00a0 requisito resulta contrario al mandato superior de progresividad en materia de \u00a0 seguridad social desde su expedici\u00f3n, por cuanto impuso a los usuarios una \u00a0 obligaci\u00f3n m\u00e1s gravosa a las ya existentes para acceder a la pensi\u00f3n de \u00a0 invalidez, tal como lo explic\u00f3 la Corte Constitucional en sentencia C-428 de \u00a0 2009. Raz\u00f3n por la cual, la demandada incurri\u00f3 en un defecto por violaci\u00f3n \u00a0 directa de la Constituci\u00f3n en su decisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>En este caso, aun cuando la fecha de \u00a0 estructuraci\u00f3n de la invalidez fue anterior a la decisi\u00f3n de inexequibilidad del \u00a0 requisito de fidelidad al sistema, este presupuesto no debi\u00f3 exigirse en sede de \u00a0 casaci\u00f3n por ser contrario al mandato constitucional de progresividad en materia \u00a0 de seguridad social en pensiones y por haber sido retirado del ordenamiento \u00a0 jur\u00eddico por esta Corporaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>2. Con base en lo anterior, la Sala Plena de \u00a0 la Corte Constitucional revocar\u00e1 la providencia del trece (13) de julio de dos \u00a0 mil doce (2012) proferida por la Sala Civil de la Corte Suprema de Justicia, que \u00a0 declar\u00f3 la nulidad de todo lo actuado por tratarse de una tutela contra un fallo \u00a0 de la Corte Suprema, y resolvi\u00f3 no admitir la acci\u00f3n de tutela presentada por \u00a0 Elizabeth Lenis Mora contra la Sala de Casaci\u00f3n Laboral de la Corte Suprema de \u00a0 Justicia. En su lugar, conceder\u00e1 el amparo de los derechos fundamentales al \u00a0 debido proceso, al acceso a la administraci\u00f3n de justicia, a la seguridad social \u00a0 y al m\u00ednimo vital de la actora. \u00a0 \u00a0<\/p>\n<p>3. Como consecuencia de lo anterior, se \u00a0 dejar\u00e1 sin efectos la sentencia del veintid\u00f3s (22) de noviembre de dos mil once \u00a0 (2011) proferida por la Sala de Casaci\u00f3n Laboral de la Corte Suprema de \u00a0 Justicia, que cas\u00f3 la sentencia del veintiocho (28) de octubre de dos mil nueve \u00a0 (2009) dictada por la Sala Laboral del Tribunal Superior de Cali, mediante la \u00a0 cual se inaplic\u00f3 el requisito de fidelidad al sistema en el caso de la actora y \u00a0 se orden\u00f3 a la administradora de pensiones y cesant\u00edas Porvenir, el \u00a0 reconocimiento y pago de la pensi\u00f3n de invalidez a favor de Elizabeth Lenis \u00a0 Mora. Por lo tanto, se restablecer\u00e1n los efectos de esta \u00faltima providencia por \u00a0 las razones expuestas en esta providencia.\u00a0 \u00a0 \u00a0<\/p>\n<p>4. Igualmente, se ordenar\u00e1 a Porvenir S.A. \u00a0 que, dentro de los quince (15) d\u00edas siguientes a la notificaci\u00f3n de esta \u00a0 providencia, cumpla las \u00f3rdenes contenidas en la sentencia dictada en segunda \u00a0 instancia por la Sala Laboral del Tribunal Superior de Cali el veintiocho (28) \u00a0 de octubre de dos mil nueve (2009), dentro del proceso laboral ordinario \u00a0 iniciado por la accionante Elizabeth Lenis Mora. Para ello deber\u00e1 tener presente \u00a0 los valores actualizados de cada una de las condenas y podr\u00e1 descontar, en caso \u00a0 de haberlo hecho, lo pagado a la accionante por concepto de devoluci\u00f3n de saldos \u00a0 de la pensi\u00f3n de invalidez, sin afectar su derecho al m\u00ednimo vital. \u00a0 Adicionalmente, se aclara que al quedar vigente la sentencia proferida del \u00a0 Tribunal, no operan prescripciones distintas a las all\u00ed ordenadas, en la medida \u00a0 que la prescripci\u00f3n fue interrumpida con la presentaci\u00f3n de la demanda. \u00a0 \u00a0 \u00a0<\/p>\n<p>V. DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Plena de la Corte Constitucional, \u00a0 administrando justicia en nombre del Pueblo y por mandato de la Constituci\u00f3n, \u00a0 \u00a0<\/p>\n<p>RESUELVE \u00a0 \u00a0<\/p>\n<p>PRIMERO.- LEVANTAR la suspensi\u00f3n de t\u00e9rminos decretada por \u00a0 auto del dos (2) de octubre de dos mil diecisiete (2017). \u00a0 \u00a0<\/p>\n<p>SEGUNDO.- REVOCAR la providencia trece (13) de julio de dos mil doce (2012) proferida\u00a0 \u00a0 por la Sala Civil de la Corte Suprema de Justicia, que declar\u00f3 la nulidad de \u00a0 todo lo actuado por tratarse de una tutela contra un fallo de la Corte Suprema, \u00a0 y que resolvi\u00f3 no admitir la acci\u00f3n de tutela presentada contra la Sala de \u00a0 Casaci\u00f3n Laboral de la Corte Suprema de Justicia. En su lugar, CONCEDER \u00a0el amparo de los derechos fundamentales al debido proceso, al acceso a la \u00a0 justicia, al m\u00ednimo vital y a la seguridad social de Elizabeth Lenis Mora. \u00a0 \u00a0<\/p>\n<p>TERCERO.- DEJAR SIN EFECTOS la sentencia del veintid\u00f3s (22) de noviembre de dos mil once (2011) \u00a0 proferida por la Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia, que \u00a0 cas\u00f3 la decisi\u00f3n del veintiocho (28) de octubre de dos mil nueve (2009) dictada \u00a0 por la Sala Laboral del Tribunal Superior de Cali.\u00a0 \u00a0 \u00a0<\/p>\n<p>QUINTO.- ORDENAR a Porvenir S.A. que, dentro de los quince \u00a0 (15) d\u00edas siguientes a la notificaci\u00f3n de esta providencia, d\u00e9 cumplimiento a \u00a0 las \u00f3rdenes contenidas en la \u00a0 sentencia dictada en segunda instancia por la Sala Laboral del Tribunal Superior \u00a0 de Cali el veintiocho (28) de octubre de dos mil nueve (2009), dentro del \u00a0 proceso laboral ordinario iniciado por la accionante Elizabeth Lenis Mora, \u00a0 teniendo en cuenta los valores actualizados de cada una de las condenas y podr\u00e1 \u00a0 descontar, en caso de haberlo hecho, lo pagado a la accionante por concepto de \u00a0 devoluci\u00f3n de saldos de la pensi\u00f3n de invalidez, sin afectar su derecho al \u00a0 m\u00ednimo vital.\u00a0 \u00a0 \u00a0<\/p>\n<p>SEXTO.- Por Secretar\u00eda General, LIBRAR las \u00a0 comunicaciones previstas en el art\u00edculo 36 del Decreto Ley 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese y arch\u00edvese el \u00a0 expediente. \u00a0 \u00a0<\/p>\n<p>ALEJANDRO LINARES CANTILLO \u00a0 \u00a0<\/p>\n<p>Presidente \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 CARLOS BERNAL PULIDO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 DIANA FAJARDO RIVERA \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Magistrado\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Magistrada \u00a0 \u00a0<\/p>\n<p>LUIS GUILLERMO GUERRERO P\u00c9REZ\u00a0 \u00a0 \u00a0\u00a0ANTONIO JOS\u00c9 LIZARAZO OCAMPO \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Magistrado\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Magistrado \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0 \u00a0 GLORIA STELLA ORTIZ DELGADO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 CRISTINA PARDO SCHLESINGER\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Magistrada\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Magistrada \u00a0 \u00a0<\/p>\n<p>JOS\u00c9 FERNANDO REYES CUARTAS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0ALBERTO ROJAS R\u00cdOS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Magistrado\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Magistrado \u00a0 \u00a0<\/p>\n<p>MARTHA S\u00c1CHICA M\u00c9NDEZ \u00a0 \u00a0<\/p>\n<p>Secretaria General \u00a0 \u00a0<\/p>\n<p>[1] La accionante manifiesta padecer \u201cPorfiria\u201d. Las Porfirias \u00a0son un grupo de trastornos gen\u00e9ticos causados por problemas con la forma en que \u00a0 el cuerpo produce una sustancia llamada hemo. El hemo se encuentra en todo el \u00a0 cuerpo, especialmente en la sangre y en la m\u00e9dula \u00f3sea, donde transporta \u00a0 ox\u00edgeno. \u00a0 \u00a0<\/p>\n<p>Existen dos tipos \u00a0 principales de Porfirias: Uno es el que afecta la piel (cut\u00e1neo) y el \u00a0 otro es el que afecta el sistema nervioso. Las personas que tienen Porfiria \u00a0 cut\u00e1nea desarrollan ampollas, picaz\u00f3n e inflamaci\u00f3n en la piel cuando se exponen \u00a0 al sol. El tipo de Porfiria que afecta al sistema nervioso se llama Porfiria \u00a0 Aguda. Consulta hecha en https:\/\/medlineplus.gov\/spanish\/porphyria.html \u00a0(Noviembre 1\u00b0 de 2017 a las 10.20AM). \u00a0 \u00a0<\/p>\n<p>[2] \u201cArt\u00edculo 4o. La \u00a0 Constituci\u00f3n es norma de normas. En todo caso de incompatibilidad entre la \u00a0 Constituci\u00f3n y la ley u otra norma jur\u00eddica, se aplicar\u00e1n las disposiciones \u00a0 constitucionales. Es deber de los nacionales y de los extranjeros en Colombia \u00a0 acatar la Constituci\u00f3n y las leyes, y respetar y obedecer a las autoridades.\u201d \u00a0 \u00a0<\/p>\n<p>[3] \u201cArt\u00edculo 243. \u00a0Los fallos que la Corte dicte en ejercicio del control jurisdiccional hacen \u00a0 tr\u00e1nsito a cosa juzgada constitucional. Ninguna autoridad podr\u00e1 reproducir el \u00a0 contenido material del acto jur\u00eddico declarado inexequible por razones de fondo, \u00a0 mientras subsistan en la Carta las disposiciones que sirvieron para hacer la \u00a0 confrontaci\u00f3n entre la norma ordinaria y la Constituci\u00f3n.\u201d \u00a0 \u00a0<\/p>\n<p>[4] En el Auto 100 de \u00a0 2008, la Sala Plena de esta Corporaci\u00f3n se\u00f1al\u00f3 que a fin de evitar una flagrante \u00a0 violaci\u00f3n del derecho de acceso a la administraci\u00f3n de justicia, cuando una \u00a0 autoridad judicial se niega a admitir o a dar tr\u00e1mite a una acci\u00f3n de tutela el \u00a0 accionante cuenta con las siguientes opciones: \u00a0 \u00a0\u00a0<\/p>\n<p>(i)\u00a0 \u201cacudir a la regla \u00a0 fijada en el Auto 04 del 3 de febrero de 2004, es decir, presentar la acci\u00f3n de \u00a0 tutela ante cualquier juez (unipersonal o colegiado) o incluso ante una \u00a0 corporaci\u00f3n judicial de la misma jerarqu\u00eda de la Corte Suprema de Justicia; o \u00a0 \u00a0<\/p>\n<p>(ii) solicitar ante la Secretar\u00eda \u00a0 General de la Corte Constitucional, que radique para selecci\u00f3n la decisi\u00f3n \u00a0 proferida por la Corte Suprema de Justicia en la cual se concluy\u00f3 que la acci\u00f3n \u00a0 de tutela era absolutamente improcedente, con el fin de que surta el tr\u00e1mite \u00a0 fijado en las normas correspondientes al proceso de selecci\u00f3n. Para este efecto, \u00a0 el interesado adjuntar\u00e1 a la acci\u00f3n de tutela, la providencia donde se plasm\u00f3 la \u00a0 decisi\u00f3n que la tutela era absolutamente improcedente, as\u00ed como la providencia \u00a0 objeto de la acci\u00f3n de tutela.\u201d \u00a0 \u00a0<\/p>\n<p>[6] Folios 50-58, cuaderno \u00a0 2 del expediente. \u00a0 \u00a0<\/p>\n<p>[7] Folios 62-63, cuaderno \u00a0 2 del expediente. \u00a0 \u00a0<\/p>\n<p>[8] Ver folios 68 a 73 del \u00a0 cuaderno 2 del expediente. La administradora de pensiones y cesant\u00edas no aport\u00f3 \u00a0 la historia laboral solicitada. \u00a0 \u00a0<\/p>\n<p>[9] Los t\u00e9rminos fueron \u00a0 suspendidos durante el d\u00eda 7 de septiembre en raz\u00f3n a la visita del Papa \u00a0 Francisco a la ciudad de Bogot\u00e1 D.C. \u00a0 \u00a0<\/p>\n<p>[10] De conformidad con el \u00a0 art\u00edculo 1 del Acuerdo 02 de 2017, \u201cEl t\u00e9rmino de los proceso de tutela que \u00a0 cursen en la Sala Plena desde la entrada en vigencia del presente Acuerdo hasta \u00a0 la conclusi\u00f3n de la revisi\u00f3n de los actos legislativos, de las leyes y de los \u00a0 decretos leyes previstos en el Acto &gt;Legislativo\u00a0 01 de 2016, se extender\u00e1 \u00a0 por teres meses adicionales, para hacer viable la priorizaci\u00f3n del control \u00a0 autom\u00e1tico, \u00fanico y posterior de constitucionalidad previsto en el literal k) \u00a0 del art\u00edculo 1 y el inciso 3 del art\u00edculo 2 del citado acto legislativo (\u2026)\u201d \u00a0 \u00a0<\/p>\n<p>[11] La accionante se\u00f1ala \u00a0 que la Corte Suprema de Justicia accionada desconoci\u00f3 la sentencia C-428 de 2009 \u00a0 que declar\u00f3 inexequible el requisito de fidelidad al sistema pensional para \u00a0 obtener la pensi\u00f3n vitalicia de invalidez, el cual le fue exigido a la \u00a0 accionante por Porvenir S.A. al momento de solicitar la prestaci\u00f3n social. \u00a0 \u00a0<\/p>\n<p>[12] Corte Constitucional. \u00a0 Sentencia T-388 de 2011 (MP Jorge Iv\u00e1n Palacio Palacio. AV. Nilson Pinilla \u00a0 Pinilla). \u00a0 \u00a0<\/p>\n<p>[13] Decreto 2591 Art\u00edculo \u00a0 17. Esta norma fue declarada exequible en sentencia C-483 de 2008. En aquella \u00a0 oportunidad se se\u00f1al\u00f3: \u201cDe cualquier forma, se debe tener claro que la \u00a0 decisi\u00f3n de rechazo de la acci\u00f3n de tutela no hace tr\u00e1nsito a cosa juzgada y, \u00a0 por tanto, el accionante est\u00e1 legitimado para presentar la solicitud de \u00a0 protecci\u00f3n constitucional nuevamente, con el cumplimiento de los requisitos \u00a0 m\u00ednimos para su admisi\u00f3n, sin que ello pueda entenderse como el ejercicio de una \u00a0 actuaci\u00f3n temeraria. De esta forma se garantiza el derecho de acceso a la \u00a0 administraci\u00f3n de justicia y se descarta cualquier posibilidad de que el \u00a0 accionante se encuentre ante una situaci\u00f3n de denegaci\u00f3n de justicia\u201d. \u00a0 \u00a0<\/p>\n<p>[14] Decreto 2591, Art\u00edculo \u00a0 26 inciso 1: \u201c(&#8230;) Cesaci\u00f3n de \u00a0 la actuaci\u00f3n impugnada. Si estando en curso la tutela, se dictare resoluci\u00f3n, \u00a0 administrativa o judicial, que revoque, detenga o suspenda la actuaci\u00f3n \u00a0 impugnada, se declarar\u00e1 fundada la solicitud \u00fanicamente para efectos de \u00a0 indemnizaci\u00f3n y de costas, si fueren procedentes.\u201d \u00a0 \u00a0<\/p>\n<p>[15] Decreto 2591 Art\u00edculo \u00a0 26 inciso 2: \u201c(\u2026) El recurrente \u00a0 podr\u00e1 desistir de la tutela, en cuyo caso se archivar\u00e1 el expediente.\u201d \u00a0 \u00a0<\/p>\n<p>[16] Decreto 2591 Art\u00edculo \u00a0 26 inciso 3. \u201c(\u2026) Cuando el \u00a0 desistimiento hubiere tenido origen en una satisfacci\u00f3n extraprocesal de los \u00a0 derechos reclamados por el interesado, el expediente podr\u00e1 reabrirse en \u00a0 cualquier tiempo, si se demuestra que la satisfacci\u00f3n acordada ha resultado \u00a0 incumplida o tard\u00eda.\u201d \u00a0 \u00a0<\/p>\n<p>[17] Los elementos de la \u00a0 triple identidad fueron ampliamente definidos en la sentencia SU-713 de 2006 \u00a0 as\u00ed: \u201c(i) identidad de partes; (ii) identidad de causa petendi; (iii) \u00a0 identidad de objeto\u201d. \u00a0 \u00a0<\/p>\n<p>[18] El art\u00edculo 38 del \u00a0 Decreto 2591 de 1991, establece: \u201cActuaci\u00f3n temeraria. Cuando sin motivo \u00a0 expresamente justificado la misma acci\u00f3n de tutela sea presentada por la misma \u00a0 persona o su representante ante varios jueces o tribunales, se rechazar\u00e1n o \u00a0 decidir\u00e1n desfavorablemente todas las solicitudes\u201d. \u00a0 \u00a0<\/p>\n<p>[19] Debe recordarse que con el fin de reglamentar el reparto \u00a0 de las acciones de tutela, el Presidente de la Rep\u00fablica expidi\u00f3 el Decreto 1382 \u00a0 de 2000, el que en su numeral 2 del art\u00edculo 1\u00b0 establece: \u201clo accionado \u00a0 contra la Corte Suprema de Justicia, ser\u00e1 repartido a la misma \u00a0 Corporaci\u00f3n y se resolver\u00e1 por la Sala de Decisi\u00f3n que corresponda de \u00a0 conformidad con el reglamento al que se refiere el art\u00edculo 4\u00ba del mismo \u00a0 decreto\u201d. \u00a0 \u00a0<\/p>\n<p>[20] Esta posici\u00f3n fue \u00a0 reiterada por la Corte Constitucional en Auto 162 de 2007 (MP. Nilson Pinilla \u00a0 Pinilla. SV. Jaime Araujo Renter\u00eda y Humberto Sierra Porto). \u00a0 \u00a0<\/p>\n<p>[21] Corte Constitucional. \u00a0 Sentencia T-1094 de 2008 (MP. Clara In\u00e9s Vargas Hern\u00e1ndez). En este caso, el \u00a0 accionante present\u00f3 acci\u00f3n de tutela con el fin de obtener la protecci\u00f3n de los \u00a0 derechos fundamentales al debido proceso, defensa, contradicci\u00f3n y acceso a la \u00a0 administraci\u00f3n de justicia, supuestamente vulnerados por la Sala de Casaci\u00f3n \u00a0 Penal de la Corte Suprema de Justicia, \u201cpor considerar que la sentencia \u00a0 dictada por dicha autoridad judicial el 28 de mayo de 2008, en el tr\u00e1mite de \u00a0 segunda instancia dentro del proceso penal seguido contra el actor, luego de \u00a0 haber encontrado una clara inobservancia del principio de congruencia por parte \u00a0 de la Sala Penal del Tribunal Superior del Distrito Judicial de Barranquilla, en \u00a0 tanto la acusaci\u00f3n se refiri\u00f3 \u00fanicamente al delito de prevaricato por acci\u00f3n, \u00a0 mientras que la decisi\u00f3n concluy\u00f3 que existi\u00f3 prevaricato por acci\u00f3n, pero en \u00a0 concurso homog\u00e9neo y sucesivo con el mismo delito, debi\u00f3 declarar la nulidad de \u00a0 todo lo actuado, y no dictar la sentencia de reemplazo como finalmente ocurri\u00f3\u201d. \u00a0 Luego de establecer la competencia y el cumplimiento de los requisitos exigidos \u00a0 en las acciones de tutela contra providencias judiciales, la Sala de Revisi\u00f3n \u00a0 neg\u00f3 el amparo solicitado. \u00a0 \u00a0<\/p>\n<p>[22] Corte Constitucional. \u00a0 Sentencia T-633 de 2009 (MP. Mauricio Gonz\u00e1lez Cuervo. SV. Jorge Ignacio Pretelt \u00a0 Chaljub). En esta oportunidad el accionante (Embajador y Jefe de la Misi\u00f3n \u00a0 Diplom\u00e1tica de la Embajada del L\u00edbano en Colombia), present\u00f3 acci\u00f3n de tutela \u00a0 contra la Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia e invoc\u00f3 como \u00a0 violados los derechos fundamentales al debido proceso y a la doble instancia, al \u00a0 dictar fallo de \u00fanica instancia en el cual declar\u00f3 \u201c(i) la existencia de un \u00a0 contrato de trabajo entre la demandante y el Estado del L\u00edbano, (ii) que ese \u00a0 contrato de trabajo se extendi\u00f3 entre el 1 de abril de 1981 al 24 de noviembre \u00a0 de 2004; y iii) que fue terminado unilateralmente y sin\u00a0 justa causa. \u00a0En\u00a0 \u00a0 consecuencia, conden\u00f3 al Estado del L\u00edbano a pagar cierta suma de dinero\u201d.\u00a0 \u00a0 De esta acci\u00f3n de tutela conoci\u00f3 la Sala de Casaci\u00f3n Penal de la Corte Suprema \u00a0 de Justicia la cual resolvi\u00f3 no tutelar los derechos invocados. Impugnada esa \u00a0 decisi\u00f3n, la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia, resolvi\u00f3 no \u00a0 admitir a tr\u00e1mite la demanda de tutela y decret\u00f3 la nulidad de la actuaci\u00f3n \u00a0 surtida ante la Sala de Casaci\u00f3n Penal de la Corte Suprema de Justicia, a partir \u00a0 del auto admisorio, inclusive.\u00a0 Al resolver el caso, la Sala de Revisi\u00f3n \u00a0 decidi\u00f3 revocar la decisi\u00f3n de la Sala de Casaci\u00f3n Civil y confirmar la de la \u00a0 Sala de Casaci\u00f3n Penal, que neg\u00f3 el amparo del derecho. \u00a0 \u00a0<\/p>\n<p>[23] Corte Constitucional. \u00a0 Sentencia T-013 de 2011 (MP. Juan Carlos Henao P\u00e9rez). En este caso, el \u00a0 accionante solicita el amparo de su derecho fundamental de petici\u00f3n \u00a0 presuntamente vulnerado por las autoridades accionadas. La Sala de Revisi\u00f3n \u00a0 encontr\u00f3 procedente la acci\u00f3n de tutela y decidi\u00f3 conceder el amparo del derecho \u00a0 y ordenar el reconocimiento de la prestaci\u00f3n solicitada. \u00a0 \u00a0<\/p>\n<p>[24] Corte Constitucional. \u00a0 Sentencia T-859 de 2011 (MP. Humberto Sierra Porto. SV. Luis Ernesto Vargas \u00a0 Silva) El accionante solicit\u00f3 la protecci\u00f3n de los derechos fundamentales al \u00a0 debido proceso, la prevalencia del derecho sustancial, la seguridad social y el \u00a0 derecho al trabajo en condiciones dignas, que estimaba violados por la Sala \u00a0 Laboral de la Corte Suprema de Justicia. En este caso, la Sala de Revisi\u00f3n \u00a0 consider\u00f3 que la decisi\u00f3n cuestionada no hab\u00eda incurrido en defecto alguno y en \u00a0 consecuencia, neg\u00f3 el amparo solicitado. \u00a0 \u00a0<\/p>\n<p>[25] Corte Constitucional. \u00a0 Sentencia T-214 de 2012 (MP. Luis Ernesto Vargas Silva). El accionante present\u00f3 \u00a0 acci\u00f3n de tutela contra la Sala Casaci\u00f3n Penal de la Corte Suprema de Justicia, \u00a0 por considerar que la autoridad judicial mencionada vulner\u00f3 su derecho \u00a0 fundamental al debido proceso, al decretar el cierre de la investigaci\u00f3n en su \u00a0 contra, calificar el m\u00e9rito del sumario y decidir sobre el decreto de pruebas en \u00a0 la audiencia preparatoria. La Sala de Casaci\u00f3n Civil de la Corte Suprema de \u00a0 Justicia se abstuvo de dar tr\u00e1mite a la misma, raz\u00f3n por la cual el accionante \u00a0 acudi\u00f3 directamente a la Corte Constitucional, acogi\u00e9ndose a lo dispuesto en el \u00a0 Auto 100 de 2008 de esta Corporaci\u00f3n. La Sala de Revisi\u00f3n consider\u00f3 que la \u00a0 providencia cuestionada no incurri\u00f3 en los defectos alegados y decidi\u00f3 negar el \u00a0 amparo. \u00a0 \u00a0<\/p>\n<p>[26] Corte Constitucional. \u00a0 Sentencia T-1038 de 2012 (MP. Mauricio Gonz\u00e1lez Cuervo. AV. Mauricio Gonz\u00e1lez \u00a0 Cuervo). El actor solicit\u00f3 la protecci\u00f3n de su derecho fundamental al debido \u00a0 proceso presuntamente violentado por la Sala de Casaci\u00f3n Penal de la Corte \u00a0 Suprema de Justicia y el Tribunal Superior de Bogot\u00e1, Sala Penal, ya que en su \u00a0 criterio estas autoridades desconocieron el principio de congruencia entre \u00a0 acusaci\u00f3n y condena. La Corte Suprema de Justicia, Sala de Casaci\u00f3n Civil, \u00a0 decidi\u00f3 \u201cno admitir a tr\u00e1mite la acci\u00f3n de tutela de la referencia\u201d. Luego de \u00a0 analizar la jurisprudencia correspondiente, la Sala de Revisi\u00f3n encontr\u00f3 \u00a0 abundante jurisprudencia, tanto de la Corte Constitucional como de la Sala de \u00a0 Casaci\u00f3n Penal de la Corte Suprema de Justicia que validan la interpretaci\u00f3n de \u00a0 las normas procesales y sustanciales aplicadas por los estrados judiciales \u00a0 demandados y en consecuencia, decidi\u00f3 declarar improcedente la acci\u00f3n de tutela \u00a0 presentada. \u00a0 \u00a0<\/p>\n<p>[27] Corte Constitucional. \u00a0 Sentencia T-1095 de 2012 (MP. Luis Ernesto Vargas Silva. AV. Luis Ernesto Vargas \u00a0 Silva). El actor present\u00f3 acci\u00f3n de tutela para solicitar el amparo de sus \u00a0 derechos constitucionales al debido proceso, a la igualdad y al poder \u00a0 adquisitivo de las pensiones en su contenido de garant\u00eda a la indexaci\u00f3n de la \u00a0 primera mesada pensional, presuntamente vulnerados por las accionadas. En esta \u00a0 ocasi\u00f3n, la Sala de Revisi\u00f3n concedi\u00f3 el amparo solicitado. \u00a0 \u00a0<\/p>\n<p>[29] Corte Constitucional. \u00a0 Sentencia SU-131 de 2013 (MP. Alexei Julio. AV. Nilson Pinilla Pinilla). El \u00a0 accionante interpuso una acci\u00f3n de tutela contra la Corte Suprema de Justicia, \u00a0 Sala de Casaci\u00f3n Laboral, en la que solicit\u00f3 el amparo de sus derechos a la vida \u00a0 digna, el debido proceso y la igualdad, presuntamente desconocidos por la \u00a0 actuaci\u00f3n de la entidad accionada, que neg\u00f3 la indexaci\u00f3n de su primera mesada \u00a0 pensional. Ante la negativa de la Sala de Casaci\u00f3n Civil de la misma \u00a0 Corporaci\u00f3n, el expediente fue seleccionado y decidido por la Sala Plena de la \u00a0 Corte Constitucional, mediante sentencia que concedi\u00f3 el amparo solicitado. \u00a0 \u00a0<\/p>\n<p>[30] Corte Constitucional. \u00a0 Sentencia T-255 de 2013 (MP. Jorge Ignacio Pretelt Chaljub). En esta oportunidad \u00a0 la Corte conoci\u00f3 de varios casos, uno de ellos presentado ante el Consejo \u00a0 Superior de la Judicatura, el cual tuvo pronunciamiento de fondo en dos \u00a0 instancias y otro presentado ante la Corte Suprema de Justicia, el cual, de \u00a0 conformidad con la decisi\u00f3n de la Sala de Casaci\u00f3n Civil de dicha corporaci\u00f3n, \u00a0 no fue tramitado. Los expedientes fueron acumulados por presentar unidad de \u00a0 materia, en cuanto sus accionantes solicitan el amparo de los derechos a \u00a0 mantener el valor adquisitivo de la pensi\u00f3n, al derecho al m\u00ednimo vital y a la \u00a0 seguridad social en pensiones. Luego de analizar los casos concretos, la Sala de \u00a0 Revisi\u00f3n concedi\u00f3 el amparo de los derechos solicitados. \u00a0 \u00a0<\/p>\n<p>[31] Corte Constitucional. \u00a0 Sentencia\u00a0 T-362 de 2013 (MP. Luis Ernesto Vargas Silva. Las accionantes \u00a0 presentaron acci\u00f3n de tutela en contra de la Sala Penal de la Corte Suprema de \u00a0 Justicia, y la Sala Penal del Tribunal Superior del Distrito Judicial de Bogot\u00e1, \u00a0 invocando la protecci\u00f3n de su derecho fundamental al debido proceso, que \u00a0 consideran vulnerado por las accionadas, debido a la condena que se les impuso \u00a0 por los delitos de peculado por apropiaci\u00f3n en calidad de intervinientes, en \u00a0 concurso con fraude procesal en calidad de coautoras, ocultamiento y destrucci\u00f3n \u00a0 de documento p\u00fablico en calidad de coautoras, uso de documento p\u00fablico falso en \u00a0 calidad coautoras y falso testimonio. Luego de analizar la situaci\u00f3n particular \u00a0 de los casos concretos, la Sala de Revisi\u00f3n decidi\u00f3 negar el amparo solicitado \u00a0 por las accionantes. \u00a0 \u00a0<\/p>\n<p>[32] Corte Constitucional. \u00a0 Sentencia T-450 de 2013 (MP. Mauricio Gonz\u00e1lez Cuervo. SPV Gabriel Eduardo \u00a0 Mendoza).\u00a0 Los accionantes solicitan el amparo de sus derechos al debido \u00a0 proceso, a la seguridad social y m\u00ednimo vital, presuntamente vulnerados con la \u00a0 expedici\u00f3n de las sentencias por parte de las autoridades judiciales accionadas \u00a0 dentro del proceso ordinario laboral en las cuales se neg\u00f3 el reconocimiento y \u00a0 pago de la pensi\u00f3n de sobrevivientes a favor de los aqu\u00ed accionantes debido al \u00a0 incumplimiento del requisito de fidelidad por parte del causante. La Sala de \u00a0 Revisi\u00f3n consider\u00f3 que les asist\u00eda raz\u00f3n a los demandantes y concedi\u00f3 el amparo \u00a0 de los derechos solicitados. \u00a0 \u00a0<\/p>\n<p>[33] Corte Constitucional. \u00a0 Sentencia T-265 de 2014 (MP. Luis Guillermo Guerrero). En este caso, la \u00a0 demandante solicit\u00f3 al juez constitucional que amparara sus derechos \u00a0 fundamentales al buen nombre, a la intimidad personal y familiar, a la honra y a \u00a0 la dignidad humana, vulnerados presuntamente por la Sala de Casaci\u00f3n Penal de la \u00a0 Corte Suprema de Justicia dentro de un proceso penal, y considerar que la \u00a0 motivaci\u00f3n de la providencia que resolvi\u00f3 el recurso de casaci\u00f3n propugnaba por \u00a0 una irrestricta libertad de expresi\u00f3n, que incluso desconoc\u00eda mandatos \u00a0 constitucionales. Al analizar el caso, la Sala de Revisi\u00f3n decidi\u00f3 negar el \u00a0 amparo solicitado. \u00a0 \u00a0<\/p>\n<p>[34] Corte Constitucional. \u00a0 Sentencia SU-873 de 2014 (MP. Mar\u00eda Victoria Calle Correa). En esta oportunidad \u00a0 la accionante acudi\u00f3 a la acci\u00f3n de tutela por considerar vulnerados sus \u00a0 derechos fundamentales al debido proceso y al m\u00ednimo vital, mediante los fallos \u00a0 proferidos dentro del proceso ordinario laboral instaurado por ella contra el \u00a0 Instituto de Seguros Sociales \u2013 ISS. Luego de revisar los requisitos de \u00a0 procedencia y analizar el caso, la Sala Plena de la Corte Constitucional revoc\u00f3 \u00a0 la providencia emitida por la Sala Civil de la Corte Suprema de Justicia, que \u00a0 declar\u00f3 la nulidad de todo lo actuado por tratarse de una tutela contra un fallo \u00a0 de la Corte Suprema, y dej\u00f3 sin efectos la sentencia de primera instancia \u00a0 proferida por la Sala Penal de la Corte Suprema de Justicia, en la cual se \u00a0 declar\u00f3 improcedente el amparo por no cumplirse el requisito de inmediatez, en \u00a0 el proceso de tutela estudiado y concedi\u00f3 el amparo de los derechos \u00a0 fundamentales al debido proceso, al m\u00ednimo vital y la seguridad social de la \u00a0 actora. \u00a0 \u00a0<\/p>\n<p>[35] Corte Constitucional. \u00a0 Sentencia T-754 de 2010 (MP. Jorge Iv\u00e1n Palacio. SV. Jorge Ignacio Pretelt \u00a0 Chaljub). La accionante present\u00f3 acci\u00f3n de tutela ante el Consejo Seccional de \u00a0 la Judicatura de Cundinamarca, Sala Jurisdiccional Disciplinaria, con el fin de \u00a0 que fueran protegidos los derechos fundamentales al debido proceso, acceso a la \u00a0 administraci\u00f3n de justicia, igualdad, libertad, honra, locomoci\u00f3n y domicilio, \u00a0 al parecer vulnerados por la Corte Suprema de Justicia, Sala de Casaci\u00f3n Penal, \u00a0 al resolver el recurso extraordinario de casaci\u00f3n dentro de un proceso penal \u00a0 seguido en su contra. En esta ocasi\u00f3n, la Sala de Revisi\u00f3n decidi\u00f3 confirmar la \u00a0 sentencia del Consejo Superior de la Judicatura, Sala Jurisdiccional \u00a0 Disciplinaria, que declar\u00f3 la improcedencia del amparo deprecado. \u00a0 \u00a0<\/p>\n<p>[36] Corte Constitucional. \u00a0 Sentencia T-978 de 2011 (MP. Gabriel Eduardo Mendoza. Av. Nilson Pinilla \u00a0 Pinilla). En esta oportunidad, los accionantes acudieron al Consejo Superior de \u00a0 la Judicatura para obtener un pronunciamiento de fondo respecto de sus \u00a0 pretensiones. Una vez surtidas las instancias correspondientes, la Sala de \u00a0 Revisi\u00f3n procedi\u00f3 a revocar las decisiones revisadas y conceder el derecho \u00a0 invocado. \u00a0 \u00a0<\/p>\n<p>[37] Corte Constitucional. \u00a0 Sentencia T-357 de 2011 (MP. Gabriel Eduardo Mendoza. AV. Nilson Pinilla \u00a0 Pinilla). La accionante en esta ocasi\u00f3n solicit\u00f3 la protecci\u00f3n de sus derechos \u00a0 fundamentales al debido proceso, a la igualdad, al buen nombre y de acceso a la \u00a0 Administraci\u00f3n de Justicia, que considera vulnerados por las entidades \u00a0 accionadas debido a la condena que se le impuso por el delito de falsedad en \u00a0 documento privado, por una actuaci\u00f3n que se le atribuy\u00f3 en su calidad de \u00a0 liquidadora dentro de un proceso liquidatorio. La tutela fue inicialmente \u00a0 presentada ante la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia y \u00a0 declarada no admisible a tr\u00e1mite, raz\u00f3n por la cual, en aplicaci\u00f3n de lo \u00a0 dispuesto en el Auto 100 de 2008 de la Corte Constitucional, la acci\u00f3n fue \u00a0 nuevamente presentada ante el Consejo Seccional de la Judicatura de \u00a0 Cundinamarca. La Sala de Revisi\u00f3n decidi\u00f3 revocar la sentencia proferida por la \u00a0 Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura, que \u00a0 confirm\u00f3 la sentencia de la Sala Jurisdiccional Disciplinaria del Consejo \u00a0 Seccional de la Judicatura de Cundinamarca que declar\u00f3 la improcedencia de la \u00a0 acci\u00f3n de tutela de la referencia, y, en su lugar neg\u00f3 el amparo solicitado.\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>[38] Corte Constitucional. \u00a0 Sentencia T-183 de 2012 (MP. Mar\u00eda Victoria Calle Correa). El accionante acudi\u00f3 \u00a0 a la acci\u00f3n de tutela por considerar vulnerados sus derechos fundamentales al \u00a0 m\u00ednimo vital, el debido proceso y la seguridad social en pensiones, al no \u00a0 reconocerle el derecho a la indexaci\u00f3n de la primera mesada pensional por parte \u00a0 del Fondo de Pasivo Social de Ferrocarriles de Colombia y la Corte Suprema de \u00a0 Justicia, Sala de Casaci\u00f3n Laboral. Ante la negativa de la Sala de Casaci\u00f3n \u00a0 Civil de la Corte Suprema de Justicia, el actor acudi\u00f3 al Consejo Superior de la \u00a0 Judicatura para obtener un pronunciamiento de fondo. Surtida las instancias, la \u00a0 Sala de Revisi\u00f3n revoc\u00f3 las decisiones revisadas y concedi\u00f3 el amparo \u00a0 solicitado. \u00a0 \u00a0<\/p>\n<p>[39] Corte Constitucional. \u00a0 Sentencia SU-158 de 2013 (MP. Mar\u00eda Victoria Calle Correa. AV. Nilson Pinilla \u00a0 Pinilla). La accionante present\u00f3 acci\u00f3n de tutela contra la Sala de Casaci\u00f3n \u00a0 Laboral de la Corte Suprema de Justicia por considerar que la decisi\u00f3n adoptada \u00a0 vulner\u00f3 sus derechos al debido proceso, a la igualdad y a la seguridad social, \u00a0 al aplicar una norma que le imped\u00eda acceder al derecho prestacional solicitado. \u00a0 La acci\u00f3n fue tramitada ante el Consejo Superior de la Judicatura en virtud de \u00a0 los Autos 004 de 2004 y 100 de 2008. Surtidas las instancias procesales, la Sala \u00a0 Plena de esta Corte decidi\u00f3 revocar la decisi\u00f3n revisada y conceder el amparo \u00a0 solicitado. \u00a0 \u00a0<\/p>\n<p>[40] Corte Constitucional. \u00a0 Sentencia T-445 de 2013 (MP. Jorge Iv\u00e1n Palacio. AV. Jorge Iv\u00e1n Palacio, Nilson \u00a0 Pinilla Pinilla y Jorge Ignacio Pretelt Chaljub). Los accionantes presentaron \u00a0 acciones de tutela contra la Sala de Casaci\u00f3n Laboral de la Corte Suprema de \u00a0 Justicia por considerar vulnerados sus derechos a la seguridad social, a la \u00a0 igualdad y al debido proceso. Los procesos surtieron las instancias procesales \u00a0 ante las Salas de Casaci\u00f3n Laboral y Penal de la Corte Suprema de Justicia y el \u00a0 Consejo Superior de la Judicatura. La Sala de Revisi\u00f3n luego de analizar los \u00a0 requisitos de procedencia, revoc\u00f3 las decisiones de los jueces de instancia y \u00a0 concedi\u00f3 el amparo solicitado por los accionantes. \u00a0 \u00a0<\/p>\n<p>[41] Posici\u00f3n reiterada por \u00a0 esta Corte en Sentencias tales como T-388 de 2011 (MP. Jorge Iv\u00e1n Palacio. AV. \u00a0 Nilson Pinilla Pinilla), T-103 de 2014 (MP. Jorge Iv\u00e1n Palacio. AV. Nilson \u00a0 Pinilla Pinilla), SU-949 de 2014 (MP. Mar\u00eda Victoria Calle Correa. AV. Gabriel \u00a0 Eduardo Mendoza), SU-230 de 2015 (MP. Jorge Ignacio Pretelt Chaljub. AV. Gabriel \u00a0 Eduardo Mendoza.SV. Mar\u00eda Victoria Calle Correa, Jorge Iv\u00e1n Palacio y Luis \u00a0 Ernesto Vargas). \u00a0 \u00a0<\/p>\n<p>[42] Corte Constitucional. \u00a0 Sentencia T-555 de 1999. (MP. Jos\u00e9 Gregorio Hern\u00e1ndez) define como v\u00eda de hecho: \u00a0 \u201cLa jurisprudencia, desarrollando el concepto de la v\u00eda de hecho, ha \u00a0 destacado que \u00fanicamente se configura sobre la base de una ostensible \u00a0 transgresi\u00f3n del ordenamiento jur\u00eddico, lo cual repercute en que, distorsionado \u00a0 el sentido del proceso, las garant\u00edas constitucionales de quienes son afectados \u00a0 por la determinaci\u00f3n judicial -que entonces pierde la intangibilidad que le es \u00a0 propia- encuentren en el amparo la \u00fanica f\u00f3rmula orientada a realizar, en su \u00a0 caso, el concepto material de la justicia. Por supuesto, tal posibilidad de \u00a0 tutela no es regla general sino excepci\u00f3n, y los jueces ante quienes se solicita \u00a0 est\u00e1n obligados a examinar de manera rigurosa el caso para no desvirtuar los \u00a0 principios de autonom\u00eda funcional de la jurisdicci\u00f3n y de la cosa juzgada\u201d. \u00a0 \u00a0<\/p>\n<p>[43] El concepto de \u00a0 providencia judicial comprende tanto las sentencias como los autos que son \u00a0 proferidos por las autoridades judiciales. Sin embargo, en materia de decisiones \u00a0 adoptadas en autos interlocutorios, la Corte ha se\u00f1alado que \u00e9stas, por regla \u00a0 general, deben ser discutidas por medio de los recursos ordinarios que el \u00a0 legislador ha dispuesto para el efecto. Posici\u00f3n reiterada en las Sentencias \u00a0 T-125 de 2010 (MP. Jorge Ignacio Pretelt Chaljub), T-845 de 2013 (MP. Jorge \u00a0 Ignacio Pretelt Chaljub. AV. Luis Ernesto Vargas Silva), T-006 de 2015 (MP. \u00a0 Jorge Iv\u00e1n Palacio) y T- 037 de 2015 (MP. Jorge Ignacio Pretelt Chaljub), entre \u00a0 otras. \u00a0 \u00a0<\/p>\n<p>[44]En este aparte se \u00a0 tomara lo expuesto en la Sentencia T-310 de 2009 (MP. Luis Ernesto Vargas \u00a0 Silva). \u00a0 \u00a0<\/p>\n<p>[45] Corte Constitucional. \u00a0 Sentencia 173 de 1993 (MP. Jos\u00e9 Gregorio Hern\u00e1ndez). \u00a0 \u00a0<\/p>\n<p>[46] Corte Constitucional. \u00a0 Sentencia T-504 de 2000 (MP. Antonio Barrera Carbonell). \u00a0 \u00a0<\/p>\n<p>[47] Ver entre otras la \u00a0 Sentencia T-315 de 2005 (MP. Jaime C\u00f3rdoba Trivi\u00f1o). \u00a0 \u00a0<\/p>\n<p>[48] Corte Constitucional. \u00a0 Sentencias T-008 de 1998 (MP. Eduardo Cifuentes Mu\u00f1oz) y SU-159 de 2000 (MP. \u00a0 Manuel Jos\u00e9 Cepeda Espinosa). \u00a0 \u00a0<\/p>\n<p>[49] Corte Constitucional. \u00a0 Sentencia T-658 de 1998 (MP. Carlos Gaviria D\u00edaz). \u00a0 \u00a0<\/p>\n<p>[50] Ver al respecto \u00a0 sentencias T-088 de 1999 (MP. Jos\u00e9 Gregorio Hern\u00e1ndez Galindo) y SU-1219 de 2001 \u00a0 (MP. \u00a0Manuel Jos\u00e9 Cepeda Espinosa) \u00a0 \u00a0<\/p>\n<p>[51] Cfr. Sentencia C-590 \u00a0 de 2005 (MP. Jaime C\u00f3rdoba Trivi\u00f1o). \u00a0 \u00a0<\/p>\n<p>[52] Ver al respecto la \u00a0 sentencia T-310 de 2009 (MP. Luis Ernesto Vargas Silva). \u00a0 \u00a0<\/p>\n<p>[53] Corte Constitutionnel. \u00a0 Sentencia T-522 de 2001 (MP. Manuel Jos\u00e9 Cepeda Espinosa). \u00a0 \u00a0<\/p>\n<p>[54] Cfr. Sentencias T-462 de 2003 (MP. Eduardo Montealegre Lynett); SU-1184 de 2001 (MP. \u00a0 Eduardo Montealegre Lynett); T-1625 de 2000 (MP. Martha Victoria S\u00e1chica M\u00e9ndez) y T-1031 de 2001 (MP, Eduardo Montealegre Lynett). \u00a0 \u00a0<\/p>\n<p>[55] Cfr. Sentencia C-590 \u00a0 de 2005 (MP. Jaime C\u00f3rdoba Trivi\u00f1o). \u00a0 \u00a0<\/p>\n<p>[56] Corte Constitucional. \u00a0 Sentencia SU-159 de 2002 (MP. Manuel Jos\u00e9 Cepeda Espinosa). En el caso objeto de \u00a0 estudio, la Corte indic\u00f3 que la prueba que se hab\u00eda allegado al proceso ante la \u00a0 Sala Penal de la Corte Suprema de Justicia se hab\u00eda obtenido violando derechos \u00a0 fundamentales del procesado. En palabras de la Corporaci\u00f3n: \u201c(\u2026) el defecto \u00a0 sustantivo que convierte en v\u00eda de hecho una sentencia judicial, opera cuando la \u00a0 decisi\u00f3n que toma el juez desborda el marco de acci\u00f3n que la Constituci\u00f3n y la \u00a0 ley le reconocen al apoyarse en una norma evidentemente inaplicable al caso \u00a0 concreto, bien sea, por ejemplo (i) porque ha sido derogada y ya no produce \u00a0 ning\u00fan efecto en el ordenamiento jur\u00eddico, (ii) porque ella es claramente \u00a0 inconstitucional y el funcionario se abstuvo de aplicar la excepci\u00f3n de \u00a0 inconstitucionalidad, (iii) porque su aplicaci\u00f3n al caso concreto es \u00a0 inconstitucional, (iv) porque ha sido declarada inexequible por la propia Corte \u00a0 Constitucional o, (v) porque, a pesar de estar vigente y ser constitucional, no \u00a0 se adecua a la circunstancia f\u00e1ctica a la cual se aplic\u00f3, porque a la norma \u00a0 aplicada, por ejemplo, se le reconocen efectos distintos a lo expresamente \u00a0 se\u00f1alados por el legislador\u201d. \u00a0 \u00a0<\/p>\n<p>[57] Corte Constitucional. \u00a0 Sentencia T-949 de 2003 (MP. Eduardo Montealegre Lynett). En esta oportunidad \u00a0 manifest\u00f3: \u201c(\u2026) todo pronunciamiento de fondo por parte del juez de tutela \u00a0 respecto de la eventual afectaci\u00f3n de los derechos fundamentales con ocasi\u00f3n de \u00a0 la actividad jurisdiccional (afectaci\u00f3n de derechos fundamentales por \u00a0 providencias judiciales) es constitucionalmente admisible, solamente, cuando el \u00a0 juez haya determinado de manera previa la configuraci\u00f3n de una de las causales \u00a0 de procedibilidad; es decir, una vez haya constatado la existencia de alguno de \u00a0 los seis eventos suficientemente reconocidos por la jurisprudencia: (i) defecto \u00a0 sustantivo, org\u00e1nico o procedimental; (ii) defecto f\u00e1ctico; (iii) error \u00a0 inducido; (iv) decisi\u00f3n sin motivaci\u00f3n, (v) desconocimiento del precedente y \u00a0 (vi) violaci\u00f3n directa de la Constituci\u00f3n\u201d.\u00a0 \u00a0 \u00a0<\/p>\n<p>[58]Ver tambi\u00e9n la \u00a0 Sentencia T-462 de 2003 (MP. Eduardo Montealegre Lynett). \u00a0 \u00a0<\/p>\n<p>[59] Corte Constitucional. \u00a0 Sentencia C-590 de 2005 (MP. Jaime C\u00f3rdoba Trivi\u00f1o). \u00a0 \u00a0<\/p>\n<p>[60] Corte Constitucional. \u00a0 Sentencia T-809 de 2010 (MP. Juan Carlos Henao P\u00e9rez). Causal aplicada entre \u00a0 otras, en las sentencias T-747 de 2009 (MP. Gabriel Eduardo Mendoza Martelo); \u00a0 T-555 de 2009 (MP. Luis Ernesto Vargas Silva); T-071 de 2012 (MP. Jorge Ignacio \u00a0 Pretelt Chaljub. AV. Nilson Pinilla Pinilla) y T-088 de 2017 (MP. Mar\u00eda Victoria \u00a0 Calle Correa. SV. Luis Guillermo Guerrero P\u00e9rez). \u00a0 \u00a0<\/p>\n<p>[61] Corte Constitucional. \u00a0 Sentencia T-518 de 2013 (MP. Jorge Ignacio Pretelt Chaljub. AV. Luis Ernesto \u00a0 Vargas Silva). \u00a0 \u00a0<\/p>\n<p>[62] \u201cARTICULO. 10.- \u00a0 Objeto del sistema general de pensiones. El sistema general de pensiones tiene \u00a0 por objeto garantizar a la poblaci\u00f3n, el amparo contra las contingencias \u00a0 derivadas de la vejez, la invalidez y la muerte, mediante el reconocimiento de \u00a0 las pensiones y prestaciones que se determinan en la presente ley, as\u00ed como \u00a0 propender por la ampliaci\u00f3n progresiva de cobertura a los segmentos de poblaci\u00f3n \u00a0 no cubiertos con un sistema de pensiones\u201d. \u00a0 \u00a0<\/p>\n<p>[63] Corte Constitucional. \u00a0 Sentencias T-016 de 2011 (MP. Gabriel Eduardo Mendoza) y T- 057 de 2017 \u00a0 \u00a0<\/p>\n<p>[64] Ver art\u00edculos 41, 42 y \u00a0 43 de la Ley 100 de 1993. \u00a0 \u00a0<\/p>\n<p>[65] \u201cPor la cual se reforman algunas \u00a0 disposiciones del Sistema General de Pensiones previsto en la Ley 100 de 1993 y \u00a0 se dictan otras disposiciones\u201d. \u00a0 \u00a0<\/p>\n<p>[66] Corte Constitucional. \u00a0 Sentencia C-428 de 2009 (MP. Mauricio Gonz\u00e1lez Cuervo. SPV. Mar\u00eda Victoria \u00a0 Calle, Jorge Iv\u00e1n Palacio y Luis Ernesto Vargas). \u00a0 \u00a0<\/p>\n<p>[67] Corte Constitucional, \u00a0 sentencias T-266 de 2010 (MP. Juan Carlos Henao P\u00e9rez), T-532 de 2010, T-615 de \u00a0 2010 (MP. Luis Ernesto Vargas Silva), T-016 de 2011 (MP. Gabriel Eduardo \u00a0 Mendoza), T-453 de 2011 (MP. Nilson Pinilla Pinilla. SPV. Humberto Sierra \u00a0 Porto), T-826 de 2014 (MP. Luis Guillermo Guerrero P\u00e9rez), T-065 de 2016 (MP. \u00a0 Gloria Ortiz Delgado) y T-057 de 2017 (MP. Gabriel Eduardo Mendoza. SPV Gloria \u00a0 Ortiz Delgado). \u00a0 \u00a0<\/p>\n<p>[68] Corte Constitucional. \u00a0 Sentencia T-826 de 2014 (MP. Luis Guillermo Guerrero P\u00e9rez). \u00a0 \u00a0<\/p>\n<p>[69] En Sentencia C-539 de \u00a0 2011 (MP. Luis Ernesto Vargas Silva), esta Corte precis\u00f3 que \u201cel \u00a0 desconocimiento del precedente judicial de las Altas Cortes (\u2026), especialmente \u00a0 de la jurisprudencia constitucional, implica la afectaci\u00f3n de derechos \u00a0 fundamentales, y por tanto una vulneraci\u00f3n directa de la Constituci\u00f3n o de la \u00a0 ley, de manera que puede dar lugar a (i) responsabilidad penal, administrativa o \u00a0 disciplinaria (\u2026), (ii) la interposici\u00f3n de acciones judiciales, entre ellas de \u00a0 la acci\u00f3n de tutela contra actuaciones administrativas o providencias \u00a0 judiciales\u201d. \u00a0 \u00a0\u00a0<\/p>\n<p>[70] Corte Constitucional. \u00a0 Sentencia C-543 de 1992 (MP. Jos\u00e9 Gregorio Hern\u00e1ndez Galindo. SV. Ciro Angarita \u00a0 Bar\u00f3n, Eduardo Cifuentes Mu\u00f1oz y Alejandro Mart\u00ednez Caballero). En este mismo \u00a0 sentido se pronunci\u00f3 esta Corporaci\u00f3n en la sentencia T-001 de 1992 (MP. Jos\u00e9 \u00a0 Gregorio Hern\u00e1ndez Galindo). \u00a0 \u00a0<\/p>\n<p>[71] Corte Constitucional. \u00a0 Sentencia C-543 de 1992 \u00a0 (MP. Jos\u00e9 Gregorio Hern\u00e1ndez Galindo. SV. Ciro Angarita Bar\u00f3n, Eduardo Cifuentes \u00a0 Mu\u00f1oz y Alejandro Mart\u00ednez Caballero), en la que se declararon inconstitucionales los \u00a0 art\u00edculos 11, 12 y 40 del Decreto Ley 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>[72] En la sentencia T-043 \u00a0 de 2016 (MP. Luis Ernesto Vargas Silva. SPV. Luis Guillermo Guerrero) esta Corte \u00a0 afirm\u00f3 que: \u201c[d]e manera reiterada, la jurisprudencia de esta Corte ha \u00a0 sostenido que la acci\u00f3n de tutela debe interponerse dentro de un t\u00e9rmino \u00a0 oportuno, justo y razonable, con el fin de que el amparo no pierda la eficacia \u00a0 que el constituyente quiso otorgarle a trav\u00e9s de lo preceptuado en el art\u00edculo \u00a0 86 de la Constituci\u00f3n de 1991 . En ese sentido, si el prop\u00f3sito de esta acci\u00f3n \u00a0 constitucional es el de prevenir un da\u00f1o inminente o hacer cesar un perjuicio \u00a0 contra los derechos fundamentales, es claro que es deber del accionante evitar \u00a0 que pase un tiempo excesivo, irrazonable o injustificado desde que se present\u00f3 \u00a0 el hecho que presuntamente vulner\u00f3 sus derechos fundamentales y el momento de \u00a0 presentaci\u00f3n de la acci\u00f3n de tutela\u201d \u00a0 \u00a0<\/p>\n<p>[73] Corte Constitucional. Sentencia T-158 de 2006 \u00a0 (MP. Humberto Sierra Porto). Estas consideraciones fueron reiteradas en las \u00a0 sentencias T-590 de 2014 (MP. Martha \u00a0 Victoria S\u00e1chica M\u00e9ndez), T-069 de 2015 (MP. Martha Victoria S\u00e1chica M\u00e9ndez), T-205 de 2015 (MP. \u00a0 Gloria Stella Ortiz Delgado), T-043 de 2016 (MP. Luis Ernesto Vargas Silva. SPV. Luis Guillermo \u00a0 Guerrero). En este sentido tambi\u00e9n se ha \u00a0 pronunciado esta Corporaci\u00f3n en las sentencias T-526 de 2005 (MP. Jaime C\u00f3rdoba \u00a0 Trivi\u00f1o), T-016 de 2006 (MP. Manuel Jos\u00e9 Cepeda), T-158 de 2006 (Humberto Sierra \u00a0 Porto), T-1084 de 2006 (MP. \u00c1lvaro Tafur Galvis), T-593 de 2007 (MP. Rodrigo \u00a0 Escobar Gil), T-792 de 2007 (MP. Marco Gerardo Monroy Cabra), T-243 de 2008 (MP. \u00a0 Manuel Jos\u00e9 Cepeda), T-594 de 2008 (MP. Jaime C\u00f3rdoba Trivi\u00f1o), T-189 de 2009 \u00a0 (MP. Luis Ernesto Vargas Silva), T-265 de 2009 (MP. Humberto Sierra Porto), \u00a0 T-299 de 2009 (MP. Mauricio Gonz\u00e1lez), T-328 de 2010 (MP. Jorge Iv\u00e1n Palacio. SV \u00a0 Jorge Ignacio Pretelt Chaljub), T-1028 de 2010 (MP. Humberto Sierra Porto. AV. \u00a0 Mar\u00eda Victoria Calle y Luis Ernesto Vargas), T- 429 de 2011 (MP. Jorge Ignacio \u00a0 Pretelt Chaljub), T-998 de 2012 (MP. Mar\u00eda Victoria Calle) y T-841 de 2014 (MP. \u00a0 Mar\u00eda Victoria Calle Correa) entre otras.. All\u00ed las diferentes Salas de Revisi\u00f3n \u00a0 han hecho alusi\u00f3n a estas situaciones excepcionales al abordar la procedibilidad \u00a0 de acciones de tutela mediante las cuales se pretend\u00eda obtener acceso a una \u00a0 defensa t\u00e9cnica, a un recalculo del monto base de la pensi\u00f3n, a la indemnizaci\u00f3n \u00a0 por da\u00f1os y perjuicios, a la sustituci\u00f3n pensional, a la pensi\u00f3n de \u00a0 sobreviviente, a la pensi\u00f3n de invalidez, reintegro derivado de estabilidad \u00a0 laboral reforzada y pago de acreencias laborales a trabajadores sindicalizados \u00a0 respectivamente. \u00a0 \u00a0<\/p>\n<p>[75] La sentencia de la \u00a0 Sala de Casaci\u00f3n Laboral de la Corte Suprema de Justicia es del 22 de noviembre \u00a0 de 2011. \u00a0 \u00a0<\/p>\n<p>[76] En su escrito del 31 \u00a0 de agosto de 2017, visible a folio 50 del cuaderno 2 del expediente, la \u00a0 accionante manifiesta que es madre cabeza de hogar, que se separ\u00f3 del padre de \u00a0 sus hijos porque \u00e9ste \u201ccay\u00f3 en las drogas\u201d. Que contin\u00faa enferma y no tiene \u00a0 empleo estable. \u00a0 \u00a0<\/p>\n<p>[77] Requisito que fue \u00a0 declarado inexequible por la Corte Constitucional mediante Sentencia C-428 de \u00a0 2009 (MP. Mauricio Gonz\u00e1lez Cuervo. SPV. Mar\u00eda Victoria Calle, Jorge Iv\u00e1n \u00a0 Palacio y Luis Ernesto Vargas). \u00a0 \u00a0<\/p>\n<p>[78] En el auto En el Auto \u00a0 100 de 2008, la Sala Plena de esta Corporaci\u00f3n se\u00f1al\u00f3 que a fin de evitar una \u00a0 flagrante violaci\u00f3n del derecho de acceso a la administraci\u00f3n de justicia, \u00a0 cuando una autoridad judicial se niega a admitir o a dar tr\u00e1mite a una acci\u00f3n de \u00a0 tutela el accionante cuenta con las siguientes opciones: \u00a0 \u00a0\u00a0<\/p>\n<p>(i)\u00a0 \u201cacudir a la regla \u00a0 fijada en el Auto 04 del 3 de febrero de 2004, es decir, presentar la acci\u00f3n de \u00a0 tutela ante cualquier juez (unipersonal o colegiado) o incluso ante una \u00a0 corporaci\u00f3n judicial de la misma jerarqu\u00eda de la Corte Suprema de Justicia; o \u00a0 \u00a0<\/p>\n<p>(ii) solicitar ante la Secretar\u00eda \u00a0 General de la Corte Constitucional, que radique para selecci\u00f3n la decisi\u00f3n \u00a0 proferida por la Corte Suprema de Justicia en la cual se concluy\u00f3 que la acci\u00f3n \u00a0 de tutela era absolutamente improcedente, con el fin de que surta el tr\u00e1mite \u00a0 fijado en las normas correspondientes al proceso de selecci\u00f3n. Para este efecto, \u00a0 el interesado adjuntar\u00e1 a la acci\u00f3n de tutela, la providencia donde se plasm\u00f3 la \u00a0 decisi\u00f3n que la tutela era absolutamente improcedente, as\u00ed como la providencia \u00a0 objeto de la acci\u00f3n de tutela.\u201d \u00a0 \u00a0<\/p>\n<p>[79] La Sala de Selecci\u00f3n \u00a0 n\u00famero siete, mediante Auto del 11 de julio de 2017, seleccion\u00f3 la presente \u00a0 acci\u00f3n de tutela y la reparti\u00f3 a la Sala S\u00e9ptima de Revisi\u00f3n de Tutelas. \u00a0 \u00a0<\/p>\n<p>[80] Ver copia del fallo a \u00a0 folios 44 a 50 del cuaderno 2 del expediente. \u00a0 \u00a0<\/p>\n<p>[81] Ver copia del fallo a \u00a0 folios 51 a 72 del cuaderno 2 del expediente. \u00a0 \u00a0<\/p>\n<p>[82] Ver copia del fallo a \u00a0 folios 95 a 120 del cuaderno 2 del expediente. \u00a0 \u00a0<\/p>\n<p>[83] La accionante \u00a0 manifest\u00f3 ser madre cabeza de hogar, al separarse del padre de sus hijos por \u00a0 caer en las drogas. Ver folio 50 del cuaderno 2 del expediente. \u00a0 \u00a0<\/p>\n<p>[84] Ver folio 64 del \u00a0 cuaderno 2 del expediente.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0SU024-18 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 Sentencia SU024\/18 \u00a0 \u00a0 DERECHO DE ACCESO EFECTIVO A LA \u00a0 ADMINISTRACION DE JUSTICIA EN MATERIA DE TUTELA-Posibilidad de acudir ante cualquier \u00a0 Juez o Cuerpo colegiado para interponer la acci\u00f3n de tutela o directamente ante \u00a0 la Corte Constitucional \u00a0 \u00a0 Toda autoridad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-25893","post","type-post","status-publish","format-standard","hentry","category-sentencias-de-unificacion-2018"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/25893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=25893"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/25893\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=25893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=25893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=25893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}