{"id":25904,"date":"2024-06-28T20:12:47","date_gmt":"2024-06-28T20:12:47","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/06\/28\/su061-18\/"},"modified":"2024-06-28T20:12:47","modified_gmt":"2024-06-28T20:12:47","slug":"su061-18","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/su061-18\/","title":{"rendered":"SU061-18"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0SU061-18 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia SU061\/18 \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS \u00a0 JUDICIALES-Requisitos generales y especiales de \u00a0 procedibilidad \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS \u00a0 JUDICIALES-Irregularidad procesal debe tener efecto \u00a0 decisivo o determinante en la sentencia que se impugna \u00a0 \u00a0<\/p>\n<p>DEFECTO PROCEDIMENTAL ABSOLUTO-Configuraci\u00f3n \u00a0 \u00a0<\/p>\n<p>CARACTERIZACION DEL DEFECTO PROCEDIMENTAL POR EXCESO RITUAL MANIFIESTO-Reiteraci\u00f3n \u00a0 de jurisprudencia \u00a0 \u00a0<\/p>\n<p>El defecto procedimental por exceso ritual manifiesto puede entenderse, en \u00a0 t\u00e9rminos generales, como el apego estricto a las reglas procesales que \u00a0 obstaculizan la materializaci\u00f3n de los derechos sustanciales, la b\u00fasqueda de la \u00a0 verdad y la adopci\u00f3n de decisiones judiciales justas. En otras palabras, por la \u00a0 ciega obediencia al derecho procesal, el funcionario judicial abandona su rol \u00a0 como garante de la normatividad sustancial, para adoptar decisiones \u00a0 desproporcionadas y manifiestamente incompatibles con el ordenamiento jur\u00eddico. \u00a0 Bajo este supuesto, la validez de la decisi\u00f3n adoptada judicialmente no solo se \u00a0 determina por el cumplimiento estricto de las reglas procesales, sino que adem\u00e1s \u00a0 depende de la protecci\u00f3n de los derechos sustanciales. Por ello, ha sostenido la \u00a0 Corte, el sistema procesal moderno no puede utilizarse como una raz\u00f3n v\u00e1lida \u00a0 para negar la satisfacci\u00f3n de tales prerrogativas, en la medida que la \u00a0 existencia de las reglas procesales se justifica a partir del contenido material \u00a0 que propenden. \u00a0 \u00a0<\/p>\n<p>DEFECTO SUSTANTIVO-Presupuestos \u00a0 para su configuraci\u00f3n \u00a0 \u00a0<\/p>\n<p>El defecto \u00a0 sustantivo se presenta en los casos en que el operador jur\u00eddico aplica la norma \u00a0 de una forma claramente irregular, afectando con su decisi\u00f3n la satisfacci\u00f3n de \u00a0 prerrogativas fundamentales. En estos eventos, el error recae en la manera como \u00a0 se utiliza una disposici\u00f3n jur\u00eddica y el alcance que el juez competente le da en \u00a0 un caso particular. Por lo que, desde esta perspectiva, la jurisprudencia \u00a0 constitucional ha sostenido que el defecto sustantivo se trata de una \u00a0 \u201cinterpretaci\u00f3n y aplicaci\u00f3n de la normatividad al caso concreto [que] resulta \u00a0 contraria a los criterios m\u00ednimos de juridicidad y razonabilidad que orientan al \u00a0 sistema jur\u00eddico\u201d \u00a0 \u00a0<\/p>\n<p>JURISDICCION CONTENCIOSO ADMINISTRATIVA-Car\u00e1cter rogado \u00a0 \u00a0<\/p>\n<p>La jurisdicci\u00f3n \u00a0 de lo contencioso administrativo funciona bajo el principio de justicia rogada. \u00a0 Ello significa que, por regla general, el operador jur\u00eddico no puede actuar de \u00a0 manera oficiosa, sino que su actividad se desarrolla respecto de los cargos que \u00a0 los ciudadanos plantean en ejercicio de las acciones constitucionales y legales \u00a0 que han sido previstas por el Legislador. En otras palabras, le compete al \u00a0 administrado iniciar, impulsar y tramitar las actuaciones judiciales que le \u00a0 permitan defender sus pretensiones. De ah\u00ed que, este principio tenga dos \u00a0 implicaciones significativas. La primera, la imposibilidad de iniciar de oficio \u00a0 un tr\u00e1mite judicial, pues se entiende que la persona interesada en reclamarle a \u00a0 la Administraci\u00f3n la ocurrencia de un da\u00f1o antijur\u00eddico, tiene la carga procesal \u00a0 de presentar la demanda, exponiendo con suficiencia las razones que le sirven de \u00a0 fundamento a sus pretensiones. Por consiguiente, el A quo no puede, al momento \u00a0 de tramitar y decidir de fondo el asunto, rebasar el marco de la relaci\u00f3n \u00a0 jur\u00eddico procesal trabada por las partes. La segunda involucra, la imposibilidad \u00a0 del fallador para iniciar de oficio el tr\u00e1mite de apelaci\u00f3n, ya que son los \u00a0 sujetos procesales involucrados en la causa los que tienen el deber de sustentar \u00a0 los motivos de su inconformidad. As\u00ed visto, \u00b4\u00a0 la competencia del juez de \u00a0 alzada se restringe a los cargos que fueron formulados por las partes a trav\u00e9s \u00a0 del recurso de apelaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>JUEZ ADMINISTRATIVO-En \u00a0 casos excepcionales, debe interpretar la relaci\u00f3n jur\u00eddico procesal trabada por \u00a0 las partes y no simplemente aplicar el principio de justicia rogada \u00a0 \u00a0<\/p>\n<p>El Consejo de \u00a0 Estado ha expresado que el juez administrativo est\u00e1 en el deber de interpretar \u00a0 la relaci\u00f3n jur\u00eddico procesal trabada por las partes y no simplemente aplicar el \u00a0 principio de justicia rogada cuando: (i) la falta de t\u00e9cnica jur\u00eddica le impide \u00a0 comprender con suficiencia algunos de los presupuestos relevantes que orientan \u00a0 su labor en el proceso ; (ii) la aplicaci\u00f3n estricta de este principio \u00a0 desconozca normas o principios consagrados en la Constituci\u00f3n Pol\u00edtica; (iii) \u00a0 deje por fuera el cumplimiento de compromisos asumidos por el Estado colombiano \u00a0 en materia de derechos humanos e infracciones al derecho internacional \u00a0 humanitario y, por \u00faltimo, (iv) en la resoluci\u00f3n del caso concreto, aun \u00a0 aplic\u00e1ndose normas procesales pertinentes, se ignoran otras disposiciones \u00a0 jur\u00eddicas relevantes para la adopci\u00f3n de una adecuada decisi\u00f3n . \u00a0 \u00a0<\/p>\n<p>ACCION DE REPARACION DIRECTA-Objeto \u00a0 \u00a0<\/p>\n<p>La acci\u00f3n de \u00a0 reparaci\u00f3n directa, como su propio nombre lo indica, tiene por finalidad \u00a0 proteger la posici\u00f3n jur\u00eddica de las v\u00edctimas, es decir, de las personas que \u00a0 vieron lesionados sus intereses y derechos como resultado de \u201cun hecho, una \u00a0 omisi\u00f3n, una operaci\u00f3n administrativa o la ocupaci\u00f3n temporal o permanente del \u00a0 inmueble por causa de trabajos p\u00fablicos\u201d , as\u00ed como sucede con los miembros de \u00a0 la Fuerza P\u00fablica que sufrieron da\u00f1os en el marco del conflicto armado y que, \u00a0 como se indic\u00f3 con anterioridad, ha sido reforzada por la cl\u00e1usula general de \u00a0 responsabilidad prevista en la Constituci\u00f3n de 1991 y la jurisprudencia del juez \u00a0 especializado en la materia. \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA \u00a0 CONTRA PROVIDENCIAS JUDICIALES EN PROCESO DE REPARACION DIRECTA-Prevalencia del \u00a0 derecho sustancial en tr\u00e1mite del recurso de apelaci\u00f3n contra sentencia de \u00a0 reparaci\u00f3n directa \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA \u00a0 CONTRA PROVIDENCIAS JUDICIALES-Procedencia por defectos procedimental \u00a0 por exceso ritual manifiesto y sustantivo en proceso de reparaci\u00f3n directa, en \u00a0 su contenido indemnizatorio de miembros de la Fuerza P\u00fablica \u00a0 \u00a0<\/p>\n<p>Referencia: \u00a0 Expediente: T-6.466.259 \u00a0 \u00a0<\/p>\n<p>Asunto: Acci\u00f3n de \u00a0 tutela presentada por H\u00e9ctor Enrique y Helbert Antonio Torres Tunjacipa en \u00a0 contra del Tribunal Administrativo del Meta y del Consejo de Estado, Secci\u00f3n \u00a0 Tercera, Subsecci\u00f3n A. \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 Ponente: \u00a0 \u00a0<\/p>\n<p>LUIS GUILLERMO \u00a0 GUERRERO P\u00c9REZ \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>La Sala Plena de la Corte Constitucional, \u00a0 en ejercicio de sus competencias constitucionales y legales, procede a emitir la \u00a0 siguiente \u00a0 \u00a0<\/p>\n<p>SENTENCIA \u00a0 \u00a0<\/p>\n<p>En el proceso de revisi\u00f3n del fallo de \u00a0 tutela adoptado el 4 de octubre de 2017 por la Secci\u00f3n Quinta del Consejo de \u00a0 Estado, que confirm\u00f3 la providencia emitida el 29 de junio de 2017 por la \u00a0 Secci\u00f3n Cuarta de la misma Corporaci\u00f3n, dentro de la acci\u00f3n de tutela promovida \u00a0 por \u00a0 H\u00e9ctor Enrique y Helbert Antonio Torres Tunjacipa contra el Tribunal \u00a0 Administrativo del Meta y el Consejo de Estado, Secci\u00f3n Tercera, Subsecci\u00f3n A. \u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>I. ANTECEDENTES \u00a0 \u00a0<\/p>\n<p>Los accionantes \u00a0 solicitaron la protecci\u00f3n constitucional de los derechos a la igualdad, al \u00a0 debido proceso y al acceso a la administraci\u00f3n de justicia, al considerar que \u00a0 las autoridades judiciales demandadas, en el curso de la acci\u00f3n de reparaci\u00f3n \u00a0 directa iniciada contra la Naci\u00f3n -Ministerio de Defensa y Ej\u00e9rcito Nacional- \u00a0 incurrieron en los defectos procedimental y sustantivo. A continuaci\u00f3n, se resumen los hechos \u00a0 relevantes de la causa: \u00a0 \u00a0<\/p>\n<p>1. Hechos relevantes[1] \u00a0 \u00a0<\/p>\n<p>1.1. Los accionantes otorgaron, junto \u00a0 con sus hermanos Juan Mauricio, Luis \u00c1ngel y Elizabeth Torres Tunjacipa, poder \u00a0 especial al abogado Luis Carlos D\u00edaz \u00c1lvarez para que iniciara y llevara hasta \u00a0 su culminaci\u00f3n la acci\u00f3n de reparaci\u00f3n directa dirigida contra la Naci\u00f3n \u00a0 -Ministerio de Defensa y Ej\u00e9rcito Nacional-. Por medio de esa actuaci\u00f3n, los \u00a0 actores pretendieron la indemnizaci\u00f3n de perjuicios por el secuestro ocurrido el \u00a0 3 de agosto de 1998 cuando prestaron el servicio militar obligatorio, hasta el \u00a0 d\u00eda de su liberaci\u00f3n, producida los d\u00edas 4 y 27 de junio de 2003[2]. \u00a0 \u00a0<\/p>\n<p>1.2. Despu\u00e9s de \u00a0 efectuados los alegatos de conclusi\u00f3n, la parte actora radic\u00f3 oficio ante el \u00a0 Tribunal Administrativo del Meta, autoridad que le correspondi\u00f3 la decisi\u00f3n de \u00a0 primera instancia, revocando el referido poder y solicitando, en cambio, el \u00a0 reconocimiento de la se\u00f1ora Yolanda Guerrero Acosta como nueva apoderada \u00a0 judicial[3]. \u00a0 Para tales efectos, el proceso ingres\u00f3 al despacho del magistrado ponente, quien \u00a0 mediante Auto del 17 de septiembre de 2008, manifest\u00f3 que \u201cprevio a realizar \u00a0 el estudio de fondo de la presente causa, se ordena por Secretar\u00eda efectuar la \u00a0 refoliaci\u00f3n de las piezas procesales que conforman el expediente\u201d[4]. \u00a0 \u00a0<\/p>\n<p>1.3. Sin pronunciarse \u00a0 sobre la solicitud de reconocimiento de la personer\u00eda jur\u00eddica de la nueva \u00a0 apoderada judicial, a trav\u00e9s de la Sentencia del 30 de septiembre de 2008, el \u00a0 Tribunal Administrativo del Meta neg\u00f3 las pretensiones de la demanda de \u00a0 reparaci\u00f3n directa, al considerar que el extremo demandante no logr\u00f3 acreditar \u00a0 la actuaci\u00f3n negligente u omisiva del Ej\u00e9rcito Nacional[5]. \u00a0 \u00a0<\/p>\n<p>1.4. En contra de la \u00a0 decisi\u00f3n adoptada por el Tribunal Administrativo del Meta, el abogado inicial \u00a0 interpuso recurso de apelaci\u00f3n \u201cen la condici\u00f3n de apoderado de la parte \u00a0 demandante\u201d[6]. \u00a0Dicho mecanismo fue concedido por el A quo y, con posterioridad, \u00a0 admitido por el Consejo de Estado, sin efectuarse pronunciamiento alguno \u00a0 respecto de la solicitud de los accionantes o la legitimidad del abogado para \u00a0 actuar en la causa controvertida[7]. Bajo la \u00a0 misma calidad, el abogado present\u00f3 los alegatos de conclusi\u00f3n en el tr\u00e1mite de \u00a0 la segunda instancia, precisando que representaba los intereses de H\u00e9ctor \u00a0 Enrique, Helbert Antonio, Juan Mauricio, Luis \u00c1ngel y Elizabeth Torres Tunjacipa[8]. \u00a0 \u00a0<\/p>\n<p>1.5. Mediante \u00a0 distintos memoriales allegados al Consejo de Estado[9], \u00a0 los accionantes revocaron el poder a la abogada Yolanda Guerrero Acosta para \u00a0 ratific\u00e1rselo a Luis Carlos D\u00edaz \u00c1lvarez, en vista de que \u201chasta la fecha no \u00a0 ha aportado pruebas, ni ha estado pendiente del mismo, (\u2026) tampoco ha sido \u00a0 posible ubicarla, ni telef\u00f3nicamente, con el fin de solicitarle brinde un \u00a0 informe detallado del proceso en curso\u201d[10]. \u00a0 En consecuencia, en Auto fechado el 10 de febrero de 2012, se reconoci\u00f3 \u00a0 nuevamente personer\u00eda jur\u00eddica al abogado inicial para actuar como apoderado de \u00a0 H\u00e9ctor Enrique y Herbert Antonio[11]. \u00a0 \u00a0<\/p>\n<p>1.6. El Consejo de \u00a0 Estado, \u00a0 Secci\u00f3n Tercera, Subsecci\u00f3n A., mediante providencia del 27 de abril de 2016, \u00a0 revoc\u00f3 la sentencia proferida en primera instancia por el Tribunal \u00a0 Administrativo del Meta, para en su lugar, conceder las pretensiones de la parte \u00a0 demandante, al comprobarse la existencia de un hecho da\u00f1oso (la incapacidad \u00a0 permanente y relativa de los accionantes), as\u00ed como el nexo de causalidad entre \u00a0 el da\u00f1o y la prestaci\u00f3n del servicio militar obligatorio. De esta manera, \u00a0 sostuvo la responsabilidad patrimonial y administrativa del Estado por la \u00a0 relaci\u00f3n de especial sujeci\u00f3n en la que se encontraban los soldados regulares[12]. \u00a0 \u00a0<\/p>\n<p>Sin embargo, en la providencia citada, el \u00a0 Consejo de Estado neg\u00f3 el reconocimiento de la indemnizaci\u00f3n de perjuicios a los \u00a0 actores, bajo el argumento de que \u201cmediante escrito presentado el 29 de \u00a0 julio de 2010 (\u2026) revocaron el poder inicial y se lo concedieron a otra abogada \u00a0 para que actuara en su representaci\u00f3n\u201d, por lo que as\u00ed visto \u201c\u00fanicamente se \u00a0 analizar\u00eda el tema de la procedencia de los perjuicios morales ocasiones a los \u00a0 se\u00f1ores Juan Mauricio, Luis \u00c1ngel y Elizabeth, toda vez que el apoderado de \u00a0 ellos s\u00ed impugn\u00f3 la decisi\u00f3n de primera instancia\u201d[13]. \u00a0 \u00a0<\/p>\n<p>1.7. Finalmente, \u00a0 contra la exclusi\u00f3n de los accionantes, el apoderado judicial interpuso las \u00a0 solicitudes de aclaraci\u00f3n y adici\u00f3n a la sentencia de segunda instancia, las \u00a0 cuales fueron resueltas negativamente el 14 de septiembre de 2016. Seg\u00fan afirm\u00f3 \u00a0 el Consejo de Estado, el objetivo de las peticiones no era esclarecer un \u00a0 elemento ambiguo de la providencia, sino lo que pretend\u00eda era corregir una \u00a0 situaci\u00f3n que se surti\u00f3 libremente por las partes[14]. \u00a0 \u00a0<\/p>\n<p>2. Fundamento de la acci\u00f3n de tutela \u00a0 \u00a0 \u00a0<\/p>\n<p>2.1. Debido a los \u00a0 anteriores hechos, el 28 de marzo de 2017 H\u00e9ctor Enrique y Helbert Antonio \u00a0 radicaron la acci\u00f3n de tutela que actualmente se analiza, con el prop\u00f3sito de \u00a0 que fueran protegidos sus derechos fundamentales a la igualdad, al debido \u00a0 proceso y al acceso a la administraci\u00f3n de justicia. Para ello, solicitaron la \u00a0 modificaci\u00f3n de la Sentencia del 27 de abril de 2016, proferida por el Consejo \u00a0 de Estado, Secci\u00f3n Tercera, Subsecci\u00f3n A., en el sentido de que les reconozcan \u00a0 la indemnizaci\u00f3n por los perjuicios ocasionados como v\u00edctimas directas del \u00a0 secuestro. Para sustentar la anterior pretensi\u00f3n, adujeron que en el curso de la \u00a0 acci\u00f3n de reparaci\u00f3n directa las autoridades judiciales demandadas incurrieron \u00a0 en una doble causal de procedibilidad de la acci\u00f3n de tutela. \u00a0 \u00a0<\/p>\n<p>2.2. En primer lugar, incurrieron en \u00a0 un defecto procedimental por exceso ritual manifiesto, al desconocer que \u00a0 la acci\u00f3n de reparaci\u00f3n directa tiene como finalidad indemnizar a las v\u00edctimas \u00a0 del da\u00f1o antijur\u00eddico. En particular, sostuvieron que la aplicaci\u00f3n de normas de \u00a0 car\u00e1cter procedimental \u2013como las que contempla el recurso de apelaci\u00f3n- no \u00a0 pueden llegar a un rigor judicial que sacrifique la satisfacci\u00f3n de los derechos \u00a0 sustanciales, la exigencia de justicia frente al secuestro y la verdad objetiva \u00a0 de los hechos. Menos a\u00fan, en los eventos que el propio juzgador declara la \u00a0 responsabilidad de la Administraci\u00f3n por los hechos que son objeto de \u00a0 controversia judicial, como sucedi\u00f3 en su caso espec\u00edfico. \u00a0 \u00a0<\/p>\n<p>En consecuencia, consideraron que el \u00a0 Consejo de Estado se distanci\u00f3 de las normas constitucionales y de los \u00a0 principios que rigen la administraci\u00f3n de justicia, alegando la aplicaci\u00f3n de \u00a0 reglas procedimentales que, de forma evidente, realzan las v\u00edas procesales en \u00a0 menoscabo de las obligaciones de protecci\u00f3n y reparaci\u00f3n del Estado para las \u00a0 v\u00edctimas de graves violaciones a los derechos humanos.\u00a0 \u00a0 \u00a0<\/p>\n<p>2.3. En segundo \u00a0 lugar, afirmaron la existencia de un defecto sustantivo en el tr\u00e1mite de \u00a0 la acci\u00f3n de reparaci\u00f3n directa, al aplicarse en indebida forma el art\u00edculo 69 \u00a0 del C\u00f3digo de Procedimiento Civil, en la medida que, desde la perspectiva de los \u00a0 accionantes, la norma jur\u00eddica exige el reconocimiento expreso de la personer\u00eda \u00a0 jur\u00eddica al nuevo apoderado judicial o, en su defecto, la aprobaci\u00f3n de la \u00a0 revocatoria del poder al antiguo representante. Bajo este supuesto, argumentaron \u00a0 que ni el Tribunal Administrativo del Meta, ni el Consejo de Estado, \u00a0 reconocieron personer\u00eda a la abogada Yolanda Guerrero Acosta, como tampoco \u00a0 aceptaron la terminaci\u00f3n del poder del apoderado Luis Carlos D\u00edaz \u00c1lvarez. En \u00a0 consecuencia, para la parte actora, la apelaci\u00f3n que efectu\u00f3 el apoderado \u00a0 inicial se hizo extensiva a sus intereses judiciales. \u00a0 \u00a0<\/p>\n<p>3. Actuaciones en el tr\u00e1mite de la acci\u00f3n de tutela \u00a0 \u00a0<\/p>\n<p>3.1. La acci\u00f3n de \u00a0 tutela fue asignada a la Secci\u00f3n Cuarta del Consejo de Estado, la cual orden\u00f3 \u00a0 notificar el libelo de la demanda al Tribunal Administrativo del Meta y al \u00a0 Consejo de Estado, Secci\u00f3n Tercera[15], como \u00a0 autoridades judiciales demandadas, as\u00ed como a los terceros interesados en el \u00a0 resultado del proceso de tutela[16]. \u00a0 \u00a0<\/p>\n<p>3.2. Cumplido el t\u00e9rmino para el \u00a0 efecto, el Tribunal Administrativo del Meta radic\u00f3 escrito ante el Consejo de \u00a0 Estado, solicitando que se negaran las pretensiones de la demanda, en la medida \u00a0 que la acci\u00f3n de tutela lo que pretend\u00eda, en el fondo, era subsanar la \u00a0 negligencia en que incurri\u00f3 la apoderada Yolanda Guerrero Acosta, designada \u00a0 voluntariamente por los demandantes. \u00a0 \u00a0<\/p>\n<p>De igual manera, indic\u00f3 que la \u00a0 terminaci\u00f3n del mandato judicial opera, de conformidad con lo previsto en el \u00a0 art\u00edculo 69 del C\u00f3digo de Procedimiento Civil, desde el momento en que el \u00a0 poderdante informa al juez la designaci\u00f3n de un nuevo abogado, no como \u00a0 err\u00f3neamente se expone en la demanda de tutela. Por consiguiente, no resulta \u00a0 admisible que el recurso de apelaci\u00f3n presentado por su anterior apoderado les \u00a0 favorezca, cuando quien incurri\u00f3 en una omisi\u00f3n fue la representante \u00a0 voluntariamente designada por los accionantes. \u00a0 \u00a0<\/p>\n<p>3.3. De otro lado, el \u00a0 abogado Luis Carlos D\u00edaz \u00c1lvarez alleg\u00f3 escrito ante el Consejo de Estado \u00a0 coadyuvando la solicitud de los accionantes. En ese sentido, sostuvo que las \u00a0 autoridades judiciales demandadas siempre le reconocieron legitimidad para \u00a0 representar los intereses de todos los demandantes en el proceso de reparaci\u00f3n \u00a0 directa que era objeto de cuestionamiento. Por ello, consider\u00f3 que resulta \u00a0 jur\u00eddicamente admisible la acci\u00f3n de tutela y la reclamaci\u00f3n de las v\u00edctimas \u00a0 directas del secuestro[17]. \u00a0 \u00a0<\/p>\n<p>3.4. En un sentido \u00a0 similar, se pronunciaron Juan Mauricio, Luis \u00c1ngel y Elizabeth Torres Tunjacipa, \u00a0 hermanos de los aqu\u00ed accionantes, quienes expusieron que resulta irrazonable que \u00a0 la demanda presentada mancomunadamente sea favorable para ellos, en la calidad \u00a0 de v\u00edctimas indirectas, y no para los accionantes, de quienes justamente se \u00a0 derivan sus derechos en el proceso administrativo de reparaci\u00f3n directa[18]. \u00a0 \u00a0<\/p>\n<p>3.5. No obra en el \u00a0 expediente respuesta Consejo de Estado, Secci\u00f3n Tercera, Subsecci\u00f3n A.[19], \u00a0 ni de la parte demandada en el tr\u00e1mite de la acci\u00f3n de reparaci\u00f3n directa[20]. \u00a0 \u00a0<\/p>\n<p>4. Decisi\u00f3n de primera instancia \u00a0 \u00a0<\/p>\n<p>La Secci\u00f3n Cuarta del Consejo de Estado, mediante Sentencia del 29 de junio de \u00a0 2017, declar\u00f3 improcedente el amparo solicitado tras \u00a0 considerar que la acci\u00f3n de tutela no cumpli\u00f3 con el requisito de inmediatez. En \u00a0 t\u00e9rminos generales, expuso que la decisi\u00f3n proferida por el Consejo de \u00a0 Estado, Secci\u00f3n Tercera, Subsecci\u00f3n A., se notific\u00f3 por edicto el 30 de junio de \u00a0 2016 y solo hasta el 27 de marzo de 2017 los accionantes radicaron la demanda de \u00a0 tutela. Es decir, transcurrieron aproximadamente 8 meses que, para el A quo, \u00a0 \u00a0\u201cdesborda los l\u00edmites de la razonabilidad\u201d. \u00a0 \u00a0<\/p>\n<p>5. Impugnaci\u00f3n \u00a0 \u00a0<\/p>\n<p>5.1. Dentro del \u00a0 t\u00e9rmino legal previsto para este efecto, los accionantes impugnaron la anterior \u00a0 decisi\u00f3n, explicando que el A quo examin\u00f3 de forma equivocada el \u00a0 requisito de inmediatez. Precisaron que el Consejo de Estado contabiliz\u00f3 los \u00a0 t\u00e9rminos para la procedencia de la acci\u00f3n de tutela desde el edicto de la \u00a0 sentencia emitida por el Ad quem (30 de junio de 2016) y no desde la \u00a0 constancia de ejecutoria del fallo, la cual se surti\u00f3 con posterioridad a la \u00a0 presentaci\u00f3n de las solicitudes de aclaraci\u00f3n y adici\u00f3n de la sentencia (30 de \u00a0 septiembre de 2016). Desde ese momento, hasta la presentaci\u00f3n de la tutela, \u00a0 transcurrieron aproximadamente 6 meses, plazo que para los tutelantes resulta \u00a0 claramente razonable. \u00a0 \u00a0<\/p>\n<p>5.2. Adicionalmente, \u00a0 como elemento excepcional expusieron las dificultades en las que se encontraron \u00a0 para obtener copias de la totalidad del expediente administrativo que sirvieran \u00a0 de base para justificar sus pretensiones constitucionales. Como prueba de eso, \u00a0 informaron que el 7 de marzo de 2017 presentaron una primera acci\u00f3n de tutela \u00a0 contra las autoridades judiciales demandadas en la que pretendieron, \u00a0 espec\u00edficamente, la expedici\u00f3n de copias de la totalidad de la actuaci\u00f3n \u00a0 judicial[21]. \u00a0 Sin embargo, la Secci\u00f3n Cuarta del Consejo de Estado declar\u00f3 su improcedencia \u00a0 tras considerar que no hubo prueba de la petici\u00f3n previa ante el Tribunal \u00a0 Administrativo del Meta[22]. \u00a0 \u00a0<\/p>\n<p>6. Decisi\u00f3n de segunda instancia \u00a0 \u00a0<\/p>\n<p>La Secci\u00f3n Quinta del Consejo de Estado decidi\u00f3 denegar la acci\u00f3n de \u00a0 tutela, considerando que el abogado Luis Carlos D\u00edaz \u00c1lvarez no ten\u00eda poder para \u00a0 representar los intereses de los accionantes, pues estos se lo revocaron \u00a0 voluntariamente para confer\u00edrselo a la se\u00f1ora Yolanda Guerrero Acosta, quien no \u00a0 present\u00f3 el recurso de apelaci\u00f3n, seg\u00fan la informaci\u00f3n que reposaba en el \u00a0 expediente. Para sostener su postura expuso que, de conformidad con el art\u00edculo \u00a0 69 del C\u00f3digo General del Proceso, el hecho de que las autoridades judiciales \u00a0 acusadas no le hubieran reconocido, de forma expresa, personer\u00eda jur\u00eddica a la \u00a0 abogada no puede entenderse como un obst\u00e1culo para la representaci\u00f3n judicial y, \u00a0 con ello, justificar la omisi\u00f3n de la abogada al interior del proceso\u00a0 \u00a0 administrativo, en tanto el acto proferido por el juez tiene un car\u00e1cter \u00a0 declarativo, no constitutivo. \u00a0 \u00a0<\/p>\n<p>7. Pruebas relevantes que obran en el expediente de tutela \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Copia de la Sentencia proferida el 30 de septiembre de 2008 por el Tribunal \u00a0 Administrativo del Meta, por medio de la cual se negaron las pretensiones de la \u00a0 acci\u00f3n de reparaci\u00f3n directa presentada por los aqu\u00ed accionantes[23]. \u00a0 \u00a0<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Copia de la Sentencia proferida por el Consejo de Estado, Secci\u00f3n Tercera, \u00a0 Subsecci\u00f3n A., del 27 de abril de 2016, a trav\u00e9s de la cual se declara \u00a0 patrimonial y administrativamente responsable a la Naci\u00f3n por los da\u00f1os \u00a0 antijur\u00eddicos soportados por los demandantes[24]. \u00a0 \u00a0<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Copia del expediente del proceso de reparaci\u00f3n directa iniciado por los actores \u00a0 contra la Naci\u00f3n (Ministerio de Defensa y Ej\u00e9rcito Nacional), en el que constan \u00a0 las actuaciones judiciales surtidas en primera y segunda instancia, as\u00ed como en \u00a0 el tr\u00e1mite de las solicitudes de aclaraci\u00f3n y adici\u00f3n[25]. \u00a0 \u00a0<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Copia de la demanda de tutela de fecha 27 de febrero de 2017, en la que se \u00a0 solicita la expedici\u00f3n de copias de la totalidad de la acci\u00f3n de reparaci\u00f3n \u00a0 directa[26], \u00a0 de la consulta efectuada sobre esa actuaci\u00f3n judicial[27]. \u00a0 \u00a0<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Copia de la sentencia proferida por la Secci\u00f3n Cuarta del Consejo de Estado en \u00a0 la que resolvi\u00f3 negativamente las pretensiones de la primera acci\u00f3n de tutela \u00a0 (11 de mayo de 2017)[28]. \u00a0 \u00a0<\/p>\n<p>8. Actuaciones en sede de revisi\u00f3n por la Corte Constitucional \u00a0 \u00a0 \u00a0<\/p>\n<p>8.1. En cumplimiento de lo dispuesto en el art\u00edculo \u00a0 61 del Reglamento de esta Corporaci\u00f3n, el 21 de febrero de 2018 el Magistrado \u00a0 Sustanciador someti\u00f3 a consideraci\u00f3n de la Sala Plena la posibilidad de que la \u00a0 misma asumiera el conocimiento del presente caso, por tratarse de una acci\u00f3n de \u00a0 tutela promovida contra una alta corporaci\u00f3n. En consecuencia, mediante decisi\u00f3n \u00a0 de la misma fecha, la Sala resolvi\u00f3 asumir el conocimiento del proceso de tutela \u00a0 de la referencia, para que fuera discutido y fallado por la plenaria de la Corte \u00a0 Constitucional.\u00a0 \u00a0 \u00a0<\/p>\n<p>8.2. Con posterioridad, mediante Auto del 6 de marzo de 2018, el Magistrado \u00a0 Sustanciador orden\u00f3, de conformidad \u00a0 con lo previsto en los art\u00edculos 59 y 61 del Reglamento Interno de la Corte \u00a0 Constitucional, poner a disposici\u00f3n de la Sala Plena y de las partes el \u00a0 expediente de la referencia, as\u00ed como suspender los t\u00e9rminos del respectivo \u00a0 proceso mientras se adoptaba la decisi\u00f3n correspondiente. \u00a0 \u00a0<\/p>\n<p>8.3. Por escrito del 22 de marzo de \u00a0 2018, la Secretar\u00eda General de esta Corporaci\u00f3n inform\u00f3 al Despacho sustanciador \u00a0 que el citado auto fue comunicado a las partes del proceso de tutela, as\u00ed como a \u00a0 los interesados que hicieron parte de la acci\u00f3n de reparaci\u00f3n directa. \u00a0 \u00a0<\/p>\n<p>II. CONSIDERACIONES DE LA CORTE CONSTITUCIONAL \u00a0 \u00a0<\/p>\n<p>1. Competencia \u00a0 \u00a0<\/p>\n<p>Con fundamento en lo previsto en los \u00a0 art\u00edculos 86 y 241-9 del Texto Superior, la Corte Constitucional es competente \u00a0 para revisar la acci\u00f3n de tutela de la referencia, escogida por la Sala de \u00a0 Selecci\u00f3n N\u00famero Once, a trav\u00e9s del Auto del 29 de noviembre de 2017[29]. \u00a0 \u00a0<\/p>\n<p>2. \u00a0 An\u00e1lisis de procedencia de la acci\u00f3n de tutela contra providencias judiciales[30] \u00a0 \u00a0<\/p>\n<p>Antes de considerar el problema de fondo de la presente \u00a0 controversia, la Corte Constitucional deber\u00e1 verificar que la demanda cumpla con \u00a0 los requisitos de procedencia de la acci\u00f3n de tutela contra providencias \u00a0 judiciales. Para ello, en la presente oportunidad, se pasar\u00e1n a indicar \u00a0 brevemente los requisitos generales unificados desde la emisi\u00f3n de la \u00a0 Sentencia C-590 de 2005[31], para con posterioridad y frente a cada uno examinar su \u00a0 cumplimiento en el caso concreto. \u00a0 \u00a0<\/p>\n<p>2.1. Requisitos generales \u00a0 \u00a0<\/p>\n<p>Como regla general, la Corte \u00a0 Constitucional ha establecido que la acci\u00f3n de tutela no procede para \u00a0 controvertir providencias judiciales, en vista de la necesidad de preservar los \u00a0 principios de seguridad jur\u00eddica y cosa juzgada, as\u00ed como los mandatos de \u00a0 autonom\u00eda e independencia judicial[32]. Sin \u00a0 embargo, ante supuestos f\u00e1cticos excepcionales, ha sostenido esta Corporaci\u00f3n, \u00a0 que resulta admisible la acci\u00f3n de tutela, como en el evento de que la decisi\u00f3n \u00a0 resulte abiertamente incompatible con disposiciones superiores, en especial, con \u00a0 la materializaci\u00f3n de los derechos fundamentales. Para que su procedencia sea \u00a0 posible, el actor deber\u00e1 demostrar el cumplimiento de los siguientes requisitos \u00a0 generales, asociados a las condiciones f\u00e1cticas y de procedimiento del caso[33].\u00a0 \u00a0 \u00a0<\/p>\n<p>2.1.1. Relevancia constitucional \u00a0 \u00a0<\/p>\n<p>De conformidad con lo establecido en la \u00a0 jurisprudencia, la relevancia constitucional, como condici\u00f3n de procedibilidad \u00a0 de la acci\u00f3n de tutela, debe estudiarse a partir de la presunta vulneraci\u00f3n de \u00a0 los derechos y principios de rango superior. Aunque en la pr\u00e1ctica judicial ha \u00a0 sido dif\u00edcil definir qu\u00e9 asunto tiene marcada importancia constitucional y cu\u00e1l \u00a0 no, la Corte ha manifestado que le est\u00e1 vedado al juez de tutela inmiscuirse \u00a0 en asuntos de car\u00e1cter netamente legal o decidir la interpretaci\u00f3n m\u00e1s acertada \u00a0 de una norma jur\u00eddica, sobre todo cuando no se desprende una clara transgresi\u00f3n \u00a0 de las prerrogativas constitucionales[34]. \u00a0 \u00a0<\/p>\n<p>Por ello, ha \u00a0 sostenido que, un asunto ser\u00e1 relevante cuando lejos de involucrar una cuesti\u00f3n \u00a0 legal, la resoluci\u00f3n del caso amerita interpretar el Estatuto Superior, \u00a0 aplicarlo materialmente o determinar el alcance de un derecho fundamental[35]. De ah\u00ed que, esta Corporaci\u00f3n haya \u00a0 reiterado que\u201cel juez constitucional no puede entrar a \u00a0 estudiar cuestiones que no tienen una clara y marcada importancia constitucional \u00a0 so pena de involucrarse en asuntos que corresponde definir a otras \u00a0 jurisdicciones. En consecuencia, el juez de tutela debe indicar con toda \u00a0 claridad y de forma expresa porqu\u00e9 la cuesti\u00f3n que entra a resolver es \u00a0 genuinamente una cuesti\u00f3n de relevancia constitucional que afecta los derechos \u00a0 fundamentales de las partes\u201d[36]. \u00a0 \u00a0<\/p>\n<p>Sobre esta base, \u00a0 la Corte estima que la cuesti\u00f3n que actualmente se discute indudablemente es de \u00a0 relevancia constitucional, comoquiera que se debate el alcance de derechos \u00a0 fundamentales, como la igualdad (art. 13), el debido proceso (art. 29) y el \u00a0 acceso a la administraci\u00f3n de justicia (art. 229). Adicionalmente, se considera \u00a0 relevante por el hecho de que los accionantes alegan el desconocimiento del \u00a0 principio de supremac\u00eda de lo sustancial sobre lo formal (art. 228), al \u00a0 presuntamente aplicarse las normas procesales sin considerar su calidad de \u00a0 v\u00edctimas directas. \u00a0 \u00a0<\/p>\n<p>2.1.2. Subsidiariedad \u00a0 \u00a0<\/p>\n<p>Seg\u00fan la jurisprudencia de esta \u00a0 Corporaci\u00f3n, cuando se controvierten decisiones judiciales el requisito de \u00a0 subsidiariedad se torna particularmente exigente, por lo que el juez de tutela \u00a0 debe verificar que la parte actora hubiera agotado \u201ctodos \u00a0 los medios -ordinarios y extraordinarios- de defensa judicial al alcance (\u2026), \u00a0 salvo que se trate de evitar la consumaci\u00f3n de un perjuicio iusfundamental \u00a0 irremediable\u201d[37]. \u00a0 Es decir que procede la revisi\u00f3n de una demanda de tutela en la que se discute \u00a0 la inconstitucionalidad de una providencia judicial en los eventos que: i) \u00a0 el accionante hubiera presentado los medios ordinarios y extraordinarios \u00a0 previstos por el Legislador para oponerse al contenido de la decisi\u00f3n o, en su \u00a0 defecto, ii) \u00a0la tutela se utiliza como un mecanismo transitorio a fin de evitar un \u00a0 perjuicio irremediable, en cuyo caso el juez podr\u00e1 intervenir de manera \u00a0 provisional, sin que sea necesario el agotamiento de todas las diligencias o \u00a0 instancias judiciales[38]. \u00a0 \u00a0<\/p>\n<p>A la luz de lo \u00a0 expuesto, esta Corporaci\u00f3n considera que en el presente caso el requisito de \u00a0 subsidiariedad se encuentra superado, pues respecto de la sentencia adoptada por \u00a0 la Secci\u00f3n Tercera del Consejo de Estado, en segunda instancia, el C\u00f3digo de \u00a0 Procedimiento Administrativo y de lo Contencioso Administrativo no prev\u00e9 \u00a0 recursos ordinarios. Tampoco admite una v\u00eda extraordinaria, en la medida que la \u00a0 cuesti\u00f3n debatida no constituye una causal para la revisi\u00f3n del fallo de segunda \u00a0 instancia, acorde con lo previsto en el art\u00edculo 250 de la misma normatividad. \u00a0 \u00a0<\/p>\n<p>2.1.3. Inmediatez \u00a0 \u00a0<\/p>\n<p>Como \u00a0 ha reiterado esta Corporaci\u00f3n, la inmediatez requiere que la acci\u00f3n de tutela \u00a0 sea promovida en un plazo razonable, contado a partir del momento en que se \u00a0 produce la vulneraci\u00f3n o amenaza de los derechos fundamentales. De lo contrario, \u00a0\u201cesto \u00a0 es, de permitir que la acci\u00f3n de tutela proceda meses o a\u00fan a\u00f1os despu\u00e9s de \u00a0 proferida la decisi\u00f3n, se sacrificar\u00edan los principios de cosa juzgada y \u00a0 seguridad jur\u00eddica, ya que sobre todas las decisiones judiciales se cernir\u00eda una \u00a0 absoluta incertidumbre que las desdibujar\u00eda como mecanismos institucionales \u00a0 leg\u00edtimos de resoluci\u00f3n de conflictos\u201d[39]. Por ello, \u00a0 aunque la determinaci\u00f3n del t\u00e9rmino m\u00e1ximo para radicar la tutela depende de la \u00a0 valoraci\u00f3n de los presupuestos f\u00e1cticos y jur\u00eddicos del caso, la Corte ha \u00a0 admitido que los seis meses siguientes al hecho generador de la afectaci\u00f3n \u00a0 constituyen un plazo razonable. Tan as\u00ed que, en oportunidades anteriores, ha \u00a0 bastado constatar que se present\u00f3 la tutela en ese periodo para declarar \u00a0 cumplido el requisito de inmediatez. Pasado este plazo, de hecho, le corresponde \u00a0 a la parte actora acreditar los motivos que justifican su tardanza en acudir \u00a0 ante la jurisdicci\u00f3n constitucional[40]. \u00a0 \u00a0<\/p>\n<p>En \u00a0 esta ocasi\u00f3n, la Sala Plena estima que resulta razonable el tiempo transcurrido \u00a0 entre la ejecutoria de la sentencia que puso fin al proceso de reparaci\u00f3n \u00a0 directa y la presentaci\u00f3n de la acci\u00f3n de tutela. Lo anterior, considerando que \u00a0 el fallo del 27 de abril de 2016 no se ejecutori\u00f3 el 30 de junio, como \u00a0 err\u00f3neamente lo expuso el A quo, sino el 30 de septiembre de 2016, \u00a0 despu\u00e9s de que la Secretar\u00eda General del Consejo de Estado notific\u00f3 por edicto \u00a0 el auto que resolvi\u00f3 las solicitudes de aclaraci\u00f3n y adici\u00f3n. Desde ese \u00a0 momento, hasta el 28 de marzo de 2017[41], d\u00eda en \u00a0 que se radic\u00f3 la acci\u00f3n de tutela, pasaron aproximadamente seis meses, tiempo \u00a0 que se observa oportuno para la radicaci\u00f3n del recurso de amparo. \u00a0 \u00a0<\/p>\n<p>Ahora bien, si en \u00a0 gracia de discusi\u00f3n se admitiera que el plazo resulta excesivo para la \u00a0 presentaci\u00f3n de la acci\u00f3n de tutela, como lo sostuvo el A quo, esta \u00a0 Corporaci\u00f3n considera que la demora se encuentra justificada, en este caso \u00a0 espec\u00edfico, pues la parte actora explic\u00f3 las distintas actuaciones \u00a0 administrativas y judiciales a las que se vio avocada para lograr la recolecci\u00f3n \u00a0 de la informaci\u00f3n que fuera \u00fatil a sus pretensiones, de las cuales solo obtuvo \u00a0 copia hasta el mes de marzo de 2017, d\u00edas previos a la presentaci\u00f3n de la \u00a0 tutela. \u00a0 \u00a0<\/p>\n<p>2.1.4. Irregularidad procesal \u00a0 determinante \u00a0 \u00a0<\/p>\n<p>De conformidad con la jurisprudencia \u00a0 reiterada de esta Corporaci\u00f3n, en los casos que la demanda alegue la \u00a0 configuraci\u00f3n de una irregularidad procesal, \u201cdebe quedar claro que la misma \u00a0 tiene un efecto decisivo o determinante en la sentencia que se impugna y que \u00a0 afecta los derechos fundamentales de la parte actora\u201d[42]. \u00a0No obstante lo anterior, \u201csi la \u00a0 irregularidad comporta una grave lesi\u00f3n de derechos fundamentales, tal como \u00a0 ocurre con los casos de pruebas il\u00edcitas susceptibles de imputarse como cr\u00edmenes \u00a0 de lesa humanidad, la protecci\u00f3n de tales derechos se genera independientemente \u00a0 de la incidencia que tengan en el litigio y por ello [habr\u00eda] lugar a la \u00a0 anulaci\u00f3n del juicio\u201d[43]. Dicho de otro \u00a0 modo, al juez constitucional le corresponde advertir que la irregularidad \u00a0 procesal alegada es de tal magnitud, que por la situaci\u00f3n que involucra, \u00a0 claramente pueden transgredirse garant\u00edas iusfundamentales[44]. \u00a0 \u00a0<\/p>\n<p>Analizado en los anteriores t\u00e9rminos el \u00a0 presente asunto, esta Sala considera que la controversia procesal alegada por \u00a0 los accionantes tiene un efecto determinante en la sentencia proferida por la \u00a0 Secci\u00f3n Tercera del Consejo de Estado, en particular, porque el Ad quem \u00a0 decidi\u00f3 excluirlos del reconocimiento de perjuicios econ\u00f3micos y morales. Desde \u00a0 el punto de vista del extremo demandante, la providencia judicial prim\u00f3 una \u00a0 consideraci\u00f3n formal \u2013la carga procesal de impugnar la providencia judicial- \u00a0 sobre su calidad de v\u00edctimas directas del da\u00f1o antijur\u00eddico y la materializaci\u00f3n \u00a0 de derechos sustanciales, lo que constituy\u00f3, en su sentir, una irregularidad \u00a0 procesal por exceso ritual manifiesto que debe ser valorada por el juez \u00a0 constitucional. \u00a0 \u00a0<\/p>\n<p>2.1.5. Identificaci\u00f3n de hechos y \u00a0 derechos \u00a0 \u00a0<\/p>\n<p>La doctrina constitucional ha sostenido \u00a0 que para la procedencia de la acci\u00f3n de tutela contra providencias judiciales la \u00a0 parte accionante debe identificar \u201ctanto los hechos que generaron la \u00a0 vulneraci\u00f3n como los derechos vulnerados y que hubiera alegado tal vulneraci\u00f3n \u00a0 en el proceso judicial, siempre que hubiere sido posible\u201d[45]. \u00a0 Es decir que el actor debe explicar de forma clara y razonable i) los \u00a0 hechos que conllevaron la amenaza o vulneraci\u00f3n de los derechos fundamentales, \u00a0 as\u00ed como ii) las prerrogativas constitucionales que fueron desconocidas \u00a0 por la autoridad judicial, las cuales debieron previamente plantearse en el \u00a0 proceso ordinario controvertido.\u00a0 \u00a0 \u00a0<\/p>\n<p>2.1.6. Prohibici\u00f3n de tutela \u00a0 contra tutela \u00a0 \u00a0<\/p>\n<p>Esta Corporaci\u00f3n ha se\u00f1alado que la \u00a0 acci\u00f3n de tutela resulta improcedente para cuestionar providencias judiciales \u00a0 que resuelvan demandas de tutela, de inconstitucionalidad o de nulidad por \u00a0 inconstitucionalidad[46], con lo \u00a0 que se evita que los procesos en los que se debate la protecci\u00f3n de derechos \u00a0 fundamentales est\u00e9n indefinidamente expuestos a un control jurisdiccional. \u00a0 \u201cEsto por cuanto los debates sobre la protecci\u00f3n de los derechos fundamentales \u00a0 no pueden prolongarse de manera indefinida, mucho m\u00e1s si todas las sentencias \u00a0 proferidas son sometidas a un riguroso proceso de selecci\u00f3n ante esta \u00a0 Corporaci\u00f3n, proceso en virtud del cual las sentencias no seleccionadas para \u00a0 revisi\u00f3n, por decisi\u00f3n de la sala respectiva, se tornan definitivas\u201d. \u00a0 \u00a0<\/p>\n<p>Este requisito no genera problema alguno, \u00a0 ya que el presente caso se interpone contra la decisi\u00f3n proferida por el Consejo \u00a0 de Estado el 27 de abril de 2016, en el curso de la acci\u00f3n de reparaci\u00f3n directa \u00a0 iniciada por los accionantes contra la Naci\u00f3n -Ministerio de Defensa y Ej\u00e9rcito \u00a0 Nacional-. \u00a0 \u00a0<\/p>\n<p>3. Planteamiento de la causal \u00a0 espec\u00edfica, del problema jur\u00eddico y metodolog\u00eda de la decisi\u00f3n \u00a0 \u00a0<\/p>\n<p>3.1. Verificado el \u00a0 cumplimiento de los requisitos generales, al juez le corresponde establecer si \u00a0 la demanda se enmarca, al menos, en una de las subsiguientes causales \u00a0 espec\u00edficas de procedibilidad de la acci\u00f3n de tutela contra providencias \u00a0 judiciales: (i) defecto org\u00e1nico, (ii) defecto procedimental, (iii) defecto \u00a0 f\u00e1ctico, (iv) defecto sustantivo, (v) error inducido, (vi) \u00a0 decisi\u00f3n sin motivaci\u00f3n, (vii) desconocimiento del precedente \u00a0 jurisprudencial o (viii) \u00a0violaci\u00f3n directa de la Constituci\u00f3n[47]. \u00a0 \u00a0<\/p>\n<p>Para cumplir con \u00a0 este requisito, la parte actora tiene la carga procesal de encausar la acci\u00f3n de \u00a0 tutela en atenci\u00f3n a las precitadas subreglas. Sin embargo, lo anterior no puede \u00a0 llevar al extremo de considerar que si la persona no se\u00f1ala, de manera \u00a0 expl\u00edcita, alguna de las anteriores denominaciones indicadas en la \u00a0 jurisprudencia, la tutela deba declararse improcedente. Ello, por cuanto lo \u00a0 importante es que la persona identifique los presupuestos f\u00e1cticos y de \u00a0 procedimiento del caso que le permitan inferir al juez, con total claridad, la \u00a0 causal objeto de controversia. \u00a0 \u00a0<\/p>\n<p>En la presente \u00a0 oportunidad, la Sala observa que los accionantes cumplieron con este criterio \u00a0 jurisprudencial, dado que se\u00f1alaron con total claridad que, al momento de \u00a0 proferirse la Sentencia del 27 de abril de 2016, el Consejo de Estado incurri\u00f3 \u00a0 en una doble causal de procedibilidad de la acci\u00f3n de tutela. De una parte, \u00a0 alegaron que se \u00a0 present\u00f3 un defecto procedimental por exceso de ritual manifiesto, al \u00a0 privilegiarse una consideraci\u00f3n formal sobre la materializaci\u00f3n de derechos \u00a0 fundamentales y la exigencia de justicia frente al secuestro. Y, de otra parte, \u00a0 un defecto sustantivo por la omisi\u00f3n en la aplicaci\u00f3n del art\u00edculo 69 del C\u00f3digo \u00a0 de Procedimiento Civil que exige, en su sentir, un reconocimiento expreso del \u00a0 cambio de apoderado judicial. Por consiguiente, rechazaron que aun cuando el \u00a0 Consejo de Estado declar\u00f3 la responsabilidad del Estado por los hechos que \u00a0 soportaron en su condici\u00f3n de soldados regulares, lo cierto fue que se neg\u00f3 a \u00a0 repararlos judicialmente, sosteniendo que no cumplieron con la carga procesal de \u00a0 impugnar la providencia judicial que les era desfavorable.\u00a0 \u00a0 \u00a0<\/p>\n<p>3.2. As\u00ed \u00a0 las cosas, acreditado en este caso el cumplimiento de los requisitos de \u00a0 procedibilidad de la tutela contra providencias judiciales, le corresponde a la \u00a0 Corte Constitucional resolver el siguiente problema jur\u00eddico: \u00bfUna autoridad \u00a0 judicial incurre en los defectos procedimental y sustantivo, cuando habilitada \u00a0 su competencia con la presentaci\u00f3n del recurso de apelaci\u00f3n, esta resuelve la \u00a0 situaci\u00f3n jur\u00eddica de los demandantes, quienes ostentaban la calidad de v\u00edctimas \u00a0 directas, condenando administrativa y patrimonialmente a la Naci\u00f3n por el da\u00f1o \u00a0 antijur\u00eddico que soportaron, pero se abstiene de reconocerles la indemnizaci\u00f3n \u00a0 de perjuicios, bajo el argumento de que no cumplieron con la carga procesal de \u00a0 impugnar la providencia judicial que les era desfavorable? \u00a0 \u00a0<\/p>\n<p>3.3. Para resolver \u00a0 este cuestionamiento, a continuaci\u00f3n la Sala Plena se\u00f1alar\u00e1 las \u00a0 principales pautas para la configuraci\u00f3n de los defectos (i) \u00a0 procedimental y (ii) \u00a0sustantivo, as\u00ed como (iii) algunas caracter\u00edsticas generales de la \u00a0 Jurisdicci\u00f3n de lo Contencioso Administrativo, en particular, el principio de \u00a0 justicia rogada, para con estos elementos, (iv) resolver el caso \u00a0 concreto. \u00a0 \u00a0<\/p>\n<p>4. Defecto procedimental. Noci\u00f3n y \u00a0 pautas generales \u00a0 \u00a0<\/p>\n<p>4.1. El defecto \u00a0 procedimental se causa por un error en la aplicaci\u00f3n de las normas que fijan el \u00a0 tr\u00e1mite a seguir para la resoluci\u00f3n de una controversia judicial. Sin embargo, \u00a0 no se trata de cualquier defecto respecto de las formas propias de cada juicio, \u00a0 sino uno que tenga la entidad suficiente para negar la materializaci\u00f3n de los \u00a0 derechos fundamentales. De ah\u00ed que, a lo largo del desarrollo jurisprudencial de \u00a0 esta Corporaci\u00f3n, \u00fanicamente se hayan previsto dos modalidades para la \u00a0 procedencia de la acci\u00f3n de tutela, en los eventos que las partes aleguen la \u00a0 ocurrencia de una falla de tipo procedimental. \u00a0 \u00a0<\/p>\n<p>4.2. La primera \u00a0 modalidad se presenta en los casos que el funcionario judicial competente act\u00faa \u00a0 por fuera del tr\u00e1mite legalmente establecido, manifestado en grado absoluto \u00a0 y que, sin ninguna justificaci\u00f3n v\u00e1lida, desencadena la afectaci\u00f3n de \u00a0 prerrogativas previstas en la Constituci\u00f3n y la legislaci\u00f3n vigente[48]. \u00a0 \u00a0<\/p>\n<p>Aunque en este evento el \u00e1mbito de \u00a0 interferencia del juez de tutela est\u00e1 restringido, pues se entiende que la \u00a0 autoridad judicial responsable act\u00faa en el marco de las competencias previstas \u00a0 por el Legislador, tambi\u00e9n ha indicado la Corte que cuando el operador desempe\u00f1a \u00a0 sus funciones alejado de la normatividad aplicable, su decisi\u00f3n resulta \u00a0 incompatible con los preceptos que orientan el ordenamiento jur\u00eddico[49]. Por esta raz\u00f3n, \u00a0 ha se\u00f1alado que se admite la intervenci\u00f3n excepcional del juez de tutela en \u00a0 eventos como los siguientes: \u00a0 \u00a0<\/p>\n<p>(i) Primero, cuando \u00a0 la autoridad judicial tramita el asunto que le corresponde resolver por un cauce \u00a0 completamente distinto al previsto en la ley o prescinde por su simple voluntad \u00a0 de la pr\u00e1ctica de una o de varias etapas del proceso. Bajo este supuesto, no \u00a0 solo se ha decidido casos en los que el operador ha omitido, sin ninguna \u00a0 justificaci\u00f3n razonable, el decreto y pr\u00e1ctica de pruebas o la notificaci\u00f3n de \u00a0 la actuaci\u00f3n procesal que requiere de dicha formalidad[50], sino que \u00a0 tambi\u00e9n ha examinado la aplicaci\u00f3n de t\u00e9rminos judiciales, donde el juez opta, \u00a0 sin motivaci\u00f3n, por prolongar o delimitar el tiempo con que cuentan las partes \u00a0 para intervenir en el proceso ordinario[51]. \u00a0 \u00a0 \u00a0<\/p>\n<p>(ii) En segundo lugar, \u00a0 cuando en el proceso se presenta una demora injustificada que impide la adopci\u00f3n \u00a0 de la decisi\u00f3n judicial definitiva. Esto no quiere decir que sea posible \u00a0 cuestionar mediante tutela cualquier retraso, alegando de forma general la \u00a0 existencia de una mora judicial, pues lo que se cuestiona en este supuesto es la \u00a0 propia vulneraci\u00f3n del derecho a un tr\u00e1mite judicial \u00e1gil y sin dilaciones \u00a0 injustificadas[52]. \u00a0 \u00a0<\/p>\n<p>(iii) \u00a0 Finalmente, cuando el juez de la causa desconoce las garant\u00edas m\u00ednimas del \u00a0 debido proceso[53], en especial, en los casos que el \u00a0 operador judicial limita irrazonablemente los derechos a la defensa y \u00a0 contradicci\u00f3n de los sujetos procesales, present\u00e1ndose por ello evidentes fallas \u00a0 en la defensa t\u00e9cnica que no pueden ser imputables a la persona y que, sin \u00a0 embargo, tienen un efecto decisivo en la resoluci\u00f3n del asunto controvertido[54]. \u00a0 \u00a0<\/p>\n<p>4.3. La \u00a0 segunda modalidad se configura por la adopci\u00f3n de decisiones judiciales que, \u00a0 aunque se emiten respetando el procedimiento previsto en la ley, quebrantan \u00a0 normas jur\u00eddicas que fijan el car\u00e1cter vinculante de la Constituci\u00f3n, (art. 4), \u00a0 la primac\u00eda de los derechos inalienables de la persona y, particularmente, la \u00a0 prevalencia de los derechos sustanciales cuando a las autoridades p\u00fablicas les \u00a0 corresponde administrar justicia (art. 228)[55]. \u00a0 \u00a0<\/p>\n<p>En materia de \u00a0 tutela contra providencias judiciales, por lo tanto, se ha establecido que el \u00a0 defecto procedimental por exceso ritual manifiesto puede entenderse, en \u00a0 t\u00e9rminos generales, como el apego estricto a las reglas procesales que \u00a0 obstaculizan la materializaci\u00f3n de los derechos sustanciales, la b\u00fasqueda de la \u00a0 verdad y la adopci\u00f3n de decisiones judiciales justas[56]. \u00a0 En otras palabras, por la ciega obediencia al derecho procesal, el funcionario \u00a0 judicial abandona su rol como garante de la normatividad sustancial, para \u00a0 adoptar decisiones desproporcionadas y manifiestamente incompatibles con el \u00a0 ordenamiento jur\u00eddico[57]. Bajo \u00a0 este supuesto, la validez de la decisi\u00f3n adoptada judicialmente no solo se \u00a0 determina por el cumplimiento estricto de las reglas procesales, sino que adem\u00e1s \u00a0 depende de la protecci\u00f3n de los derechos sustanciales[58]. Por ello, ha sostenido la Corte, el sistema \u00a0 procesal moderno no puede utilizarse como una raz\u00f3n v\u00e1lida para negar la \u00a0 satisfacci\u00f3n de tales prerrogativas, en la medida que la existencia de las \u00a0 reglas procesales se justifica a partir del contenido material que propenden[59]. \u00a0 \u00a0<\/p>\n<p>En consecuencia, \u00a0 en este segundo escenario, el juez de tutela deber\u00e1 hacer uso de sus facultades \u00a0 constitucionales cuando la exigencia realizada por la autoridad competente, en \u00a0 el caso particular y concreto, se advierta como un apego extremo a las reglas \u00a0 procedimentales, que sin justificaci\u00f3n razonable y dada la imposibilidad para \u00a0 cumplir con la carga procesal impuesta, su postura solo puede ser catal\u00f3gala\u00a0 \u00a0 como desproporcionada, en virtud de los hechos y medios que rodean la presunta afectaci\u00f3n \u00a0 de los derechos fundamentales[60]. \u00a0 \u00a0<\/p>\n<p>5. Defecto sustantivo. Noci\u00f3n y pautas generales \u00a0 \u00a0<\/p>\n<p>5.1. El \u00a0 defecto sustantivo se presenta en los casos en que el operador jur\u00eddico aplica \u00a0 la norma de una forma claramente irregular, afectando con su decisi\u00f3n la \u00a0 satisfacci\u00f3n de prerrogativas fundamentales[61]. \u00a0 En estos eventos, el error recae en la manera como se utiliza una disposici\u00f3n \u00a0 jur\u00eddica y el alcance que el juez competente le da en un caso particular. Por lo \u00a0 que, desde esta perspectiva, la jurisprudencia constitucional ha sostenido que \u00a0 el defecto sustantivo se trata de una \u201cinterpretaci\u00f3n y aplicaci\u00f3n de la normatividad al caso concreto \u00a0 [que] resulta contraria a los criterios m\u00ednimos de juridicidad y razonabilidad \u00a0 que orientan al sistema jur\u00eddico\u201d[62]. \u00a0 \u00a0<\/p>\n<p>Lo anterior no significa que el juez de tutela tiene la plena \u00a0 potestad para controvertir cualquier interpretaci\u00f3n realizada por la autoridad \u00a0 legalmente competente, puesto que la Constituci\u00f3n Pol\u00edtica les otorga a todas \u00a0 las autoridades que ejercen funciones jurisdiccionales la autonom\u00eda e \u00a0 independencia necesaria para elegir las normas que fundamentan la adopci\u00f3n de \u00a0 sus decisiones (Arts. 228 y 230 de la C.P.)[63]. De esta manera, los jueces gozan de \u00a0 libertad interpretativa, tanto en los casos que su labor se agota en la \u00a0 subsunci\u00f3n, como en los eventos que requiere, para una correcta decisi\u00f3n, \u00a0 superar los vac\u00edos propios de la t\u00e9cnica legislativa[64]. \u00a0 \u00a0<\/p>\n<p>5.2. Sin \u00a0 embargo, la autonom\u00eda e independencia de la que gozan las autoridades \u00a0 judiciales, ha se\u00f1alado la Corte, tampoco significa una libertad sin l\u00edmites \u00a0 para elegir las normas que fundamentan sus decisiones[65]. En otras palabras, ni la autonom\u00eda ni la \u00a0 independencia judicial pueden equiparse a la libertad absoluta del operador \u00a0 judicial para interpretar y aplicar el derecho vigente[66]. \u00a0 \u00a0<\/p>\n<p>Por esta raz\u00f3n, \u00a0 aunque el juez de tutela no est\u00e1 facultado para determinar cu\u00e1l es la aplicaci\u00f3n \u00a0 correcta de una disposici\u00f3n normativa o definir la aproximaci\u00f3n al texto \u00a0 legislativo que debi\u00f3 efectuar la autoridad judicial competente, si le \u00a0 corresponde verificar que la decisi\u00f3n no obedezca a un capricho del operador \u00a0 judicial, a trav\u00e9s del cual se sobrepasen los par\u00e1metros m\u00ednimos de juridicidad \u00a0 y racionalidad establecidos en el sistema jur\u00eddico colombiano[67]. \u00a0Dicho de otro modo, \u00a0 \u201cno puede el juez de tutela, en principio, definir cu\u00e1l es la mejor \u00a0 interpretaci\u00f3n, la m\u00e1s adecuada o razonable del derecho legislado, pues su \u00a0 funci\u00f3n se limita simplemente a garantizar que no exista arbitrariedad y a \u00a0 proteger los derechos fundamentales y no a definir el sentido y alcance de las \u00a0 normas de rango legal\u201d [68]. Bajo este entendido, la Corte ha admitido que un defecto sustantivo \u00a0 se produce en eventos como los que a continuaci\u00f3n \u00a0se indican[69]: \u00a0 \u00a0<\/p>\n<p>(i) En \u00a0 primer lugar, cuando el operador judicial excluye la aplicaci\u00f3n de normas \u00a0 jur\u00eddicas relevantes o desconoce el precedente jurisprudencial en la materia[70]. \u00a0 En estos casos lo que se reprocha es la clara omisi\u00f3n en la aplicaci\u00f3n del texto \u00a0 normativo que, sin justificaci\u00f3n alguna, cambia el sentido de la decisi\u00f3n. Como \u00a0 sucede en los eventos que: a) la autoridad judicial desconoce la norma \u00a0 prevista en el ordenamiento jur\u00eddico para resolver el asunto controvertido o, \u00a0 b) aun aplicando una disposici\u00f3n relevante, deja de lado la valoraci\u00f3n de \u00a0 otras normas que permitir\u00edan regular el caso de forma coherente y compatible con \u00a0 el ordenamiento jur\u00eddico. Adicionalmente, la jurisprudencia ha sostenido que se \u00a0 presenta un error judicial, c) en los casos en que se interpreta una \u00a0 norma de forma manifiestamente contraria al precedente previsto por una alta \u00a0 corporaci\u00f3n, ya sea en materia constitucional, administrativa o civil[71]. \u00a0 \u00a0<\/p>\n<p>(ii) En \u00a0 segundo lugar, cuando se aplica una norma jur\u00eddica equ\u00edvoca[72], es \u00a0 decir que: a) se utiliza un texto que no est\u00e1 vigente \u00a0 por cualquiera de las razones previstas en el ordenamiento jur\u00eddico (por \u00a0 ejemplo, se declar\u00f3 su derogatoria por parte del legislador o la Corte \u00a0 Constitucional, su inexequibilidad); b) el juez omite aplicar la \u00a0 excepci\u00f3n de inconstitucional, resolviendo el caso de una manera incompatible \u00a0 con disposiciones constitucionales; c) se utilizaron normas jur\u00eddicas por \u00a0 parte del operador judicial que resultan inadecuadas o impertinentes, seg\u00fan las \u00a0 circunstancias f\u00e1cticas del caso y, finalmente, d) se aplica de forma \u00a0 irretroactiva una norma jur\u00eddica en los supuestos de hecho que resulta \u00a0 legalmente inadmisible. \u00a0 \u00a0 \u00a0<\/p>\n<p>(iii) Tambi\u00e9n, cuando se interpreta indebidamente el texto jur\u00eddico[73]. Al respecto, \u00a0 la Corte Constitucional ha aceptado la procedencia de la acci\u00f3n de tutela cuando \u00a0 los jueces incurren en errores en materia interpretativa, en particular, cuando \u00a0 las providencias judiciales \u201ccarece(n) de fundamento objetivo y razonable, \u00a0 por basarse en una interpretaci\u00f3n ostensible y abiertamente contraria a la norma \u00a0 jur\u00eddica aplicable\u201d[74]. Este escenario se presenta no solo \u00a0 en los eventos que: a) la interpretaci\u00f3n realizada por el funcionario es \u00a0 contraevidente[75], \u00a0 es decir, desconoce el sentido com\u00fan de las palabras o la voluntad del \u00a0 legislador[76], sino que adem\u00e1s b) la interpretaci\u00f3n resulta irrazonable -jur\u00eddica y \u00a0 l\u00f3gicamente inaceptable-, arbitraria -sin motivaci\u00f3n- y caprichosa -con un \u00a0 fundamento inadecuado-[77]. \u00a0 \u00a0<\/p>\n<p>Respecto de este \u00a0 \u00faltimo escenario, finalmente, vale la pena reiterar que la jurisprudencia constitucional ha \u00a0 indicado que uno de los l\u00edmites de la labor interpretativa efectuada por el \u00a0 operador judicial est\u00e1 relacionado con que su interpretaci\u00f3n resulte conforme \u00a0 con la Constituci\u00f3n. \u00a0 En otras palabras, que el trabajo desarrollado libremente por el juzgador se \u00a0 conduzca por los dictados del Texto Superior, especialmente en lo \u00a0 relativo a la protecci\u00f3n de los derechos fundamentales. As\u00ed, ser\u00e1 \u00a0 inconstitucional la actuaci\u00f3n desplegada por los jueces que, de forma \u00a0 injustificada e irrazonable, supere el marco de acci\u00f3n previsto por la Carta \u00a0 Pol\u00edtica y, en contraste, ser\u00e1 constitucionalmente admisible la interpretaci\u00f3n \u00a0 judicial que guarda coherencia con la norma fundamental[78]. \u00a0 \u00a0<\/p>\n<p>6. Jurisdicci\u00f3n de lo Contencioso Administrativo. Pautas respecto \u00a0 de su car\u00e1cter rogado y la acci\u00f3n de reparaci\u00f3n directa \u00a0 \u00a0<\/p>\n<p>En vista de que \u00a0 en el presente caso los actores cuestionan la decisi\u00f3n del Consejo de Estado de \u00a0 negarles el reconocimiento de la indemnizaci\u00f3n de perjuicios econ\u00f3micos y \u00a0 morales, aun cuando declar\u00f3 responsable a la Naci\u00f3n por el secuestro del que \u00a0 fueron v\u00edctimas directas, esta Corporaci\u00f3n estima necesario realizar algunas \u00a0 referencias generales respecto de (i) el car\u00e1cter jur\u00eddico de la \u00a0 jurisdicci\u00f3n de lo contencioso administrativo y (ii) la finalidad de la \u00a0 acci\u00f3n de reparaci\u00f3n directa, para con estos elementos examinar a continuaci\u00f3n \u00a0 el papel del tribunal demandado. \u00a0 \u00a0 \u00a0<\/p>\n<p>6.1. El car\u00e1cter \u00a0 rogado de la Jurisdicci\u00f3n de lo Contencioso Administrativo. Criterios generales \u00a0 \u00a0<\/p>\n<p>6.1.1. La \u00a0 jurisdicci\u00f3n de lo contencioso administrativo funciona bajo el principio de \u00a0 justicia rogada. Ello significa que, por regla general, el operador jur\u00eddico no \u00a0 puede actuar de manera oficiosa, sino que su actividad se desarrolla respecto de \u00a0 los cargos que los ciudadanos plantean en ejercicio de las acciones \u00a0 constitucionales y legales que han sido previstas por el Legislador. En otras \u00a0 palabras, le compete al administrado iniciar, impulsar y tramitar las \u00a0 actuaciones judiciales que le permitan defender sus pretensiones[79]. De ah\u00ed que, este principio tenga dos \u00a0 implicaciones significativas. La primera, la imposibilidad de iniciar de oficio \u00a0 un tr\u00e1mite judicial, pues se entiende que la persona interesada en reclamarle a \u00a0 la Administraci\u00f3n la ocurrencia de un da\u00f1o antijur\u00eddico, tiene la carga procesal \u00a0 de presentar la demanda, exponiendo con suficiencia las razones que le sirven de \u00a0 fundamento a sus pretensiones. Por consiguiente, el A quo no puede, al \u00a0 momento de tramitar y decidir de fondo el asunto, rebasar el marco de la \u00a0 relaci\u00f3n jur\u00eddico procesal trabada por las partes. \u00a0 \u00a0<\/p>\n<p>La segunda \u00a0 involucra, la imposibilidad del fallador para iniciar de oficio el tr\u00e1mite de \u00a0 apelaci\u00f3n, ya que son los sujetos procesales involucrados en la causa los que \u00a0 tienen el deber de sustentar los motivos de su inconformidad. As\u00ed visto, la \u00a0 competencia del juez de alzada se restringe a los cargos que fueron formulados \u00a0 por las partes a trav\u00e9s del recurso de apelaci\u00f3n[80]. \u00a0 \u00a0<\/p>\n<p>6.1.2. En \u00a0 relaci\u00f3n con este \u00faltimo punto, el Legislador delimit\u00f3 con claridad la \u00a0 competencia del juez de alzada, al establecerse que a la autoridad judicial \u00a0 correspondiente no le es v\u00e1lido resolver el problema jur\u00eddico trayendo a \u00a0 colaci\u00f3n argumentos no planteados por los apelantes. De mamenra espec\u00edfica, fij\u00f3 \u00a0 en el art\u00edculo 247 de la Ley 1437 de 2011 (actual C\u00f3digo de Procedimiento \u00a0 Administrativo y de lo Contencioso Administrativo), que las partes cuentan con \u00a0 la potestad para presentar el recurso de apelaci\u00f3n contra los contenidos de la \u00a0 sentencia de primera instancia que les sean desfavorables, pero asumiendo la \u00a0 doble carga de: (i) interponer el recurso de forma oportuna y (ii) \u00a0 sustentar las razones por las cuales consideran que la decisi\u00f3n apelada \u00a0 contiene, de manera injustificada, apartes adversos a sus pretensiones. \u00a0 Cumplidas las anteriores condiciones, precis\u00f3 el Legislador, al superior \u00a0 jer\u00e1rquico le corresponde, decidir acerca de la modificaci\u00f3n, revocatoria o \u00a0 confirmaci\u00f3n del fallo de primer grado, pero \u00fanicamente respecto de los \u00a0 elementos que fueron impugnados. \u00a0 \u00a0<\/p>\n<p>Esta misma \u00a0 consideraci\u00f3n fue prevista en el art\u00edculo 320 de la Ley 1564 de 2012 (actual \u00a0 C\u00f3digo General del Proceso), que siendo compatible con la naturaleza de los \u00a0 procesos y actuaciones que corresponden a la jurisdicci\u00f3n de lo contencioso \u00a0 administrativo, establece como la finalidad del recurso de apelaci\u00f3n que \u201cel \u00a0 superior examine la cuesti\u00f3n decidida, \u00fanicamente en relaci\u00f3n con los reparos \u00a0 concretos formulados por el apelante, para que el superior revoque o reforme la \u00a0 decisi\u00f3n\u201d. Y, en igual sentido, el art\u00edculo 328 de la misma normatividad que \u00a0 indica que la competencia del superior se restringe a \u201clos argumentos \u00a0 expuestos por el apelante, sin perjuicio de las decisiones que deba adoptar de \u00a0 oficio, en los casos previstos por la ley\u201d. \u00a0 \u00a0<\/p>\n<p>6.1.3. En el \u00a0 mismo sentido, el Consejo de Estado, m\u00e1ximo \u00f3rgano judicial especializado en la \u00a0 materia, ha enfatizado en el car\u00e1cter rogado de la jurisdicci\u00f3n de lo \u00a0 contencioso administrativo, reiterando que el juez de alzada solo puede \u00a0 pronunciarse sobre temas que hayan sido planteados y sustentados por las partes \u00a0 procesales, pues de lo contrario la actuaci\u00f3n judicial no solo representar\u00eda un \u00a0 abuso de las atribuciones constitucionales y legales otorgadas al juez, sino que \u00a0 adem\u00e1s vulnerar\u00eda los derechos a la defensa y contradicci\u00f3n de los sujetos \u00a0 que no hicieron parte de la actuaci\u00f3n judicial[81]. \u00a0 \u00a0<\/p>\n<p>En espec\u00edfico, ha sostenido que \u201ca \u00a0 trav\u00e9s del recurso de apelaci\u00f3n se ejerce el derecho de impugnaci\u00f3n contra una \u00a0 determinada decisi\u00f3n judicial -en este caso la que contiene una sentencia-, por \u00a0 lo cual corresponde al recurrente confrontar los argumentos que el juez de \u00a0 primera instancia consider\u00f3 para tomar su decisi\u00f3n, con las propias \u00a0 consideraciones del recurrente, para efectos de solicitarle al juez de superior \u00a0 jerarqu\u00eda funcional que decida sobre los puntos o asuntos que se cuestionan ante \u00a0 la segunda instancia. (\u2026) Para el juez de segunda instancia su marco fundamental \u00a0 de competencia lo constituyen las referencias conceptuales y argumentativas que \u00a0 se aducen y esgrimen en contra de la decisi\u00f3n que se hubiere adoptado en primera \u00a0 instancia, por lo cual, en principio, los dem\u00e1s aspectos, diversos a los \u00a0 planteados por el recurrente se excluyen del debate en la instancia superior\u201d[82]. \u00a0 \u00a0<\/p>\n<p>6.1.5. A \u00a0 trav\u00e9s de las Sentencias\u00a0 C-197 de 1999[83], C-415 \u00a0 de 2012[84] y \u00a0T-553 \u00a0 de 2012[85], por \u00a0 ejemplo, la Corte Constitucional ha sostenido que deber\u00e1 valorarse la aplicaci\u00f3n \u00a0 del principio de justicia rogada cuando, en el caso espec\u00edfico (i) \u00a0la interpretaci\u00f3n que se haga de ella, desconozca la protecci\u00f3n efectiva \u00a0 que se establece en la Constituci\u00f3n Pol\u00edtica para los derechos fundamentales de \u00a0 aplicaci\u00f3n inmediata (art. 85) o, (ii) se evidencie una absoluta \u00a0 incompatibilidad con mandatos previstos en el Texto Superior. De hecho, \u00a0 se ha estimado que, aun cuando no resulta irrazonable ni desproporcionado que el \u00a0 Legislador haya impuesto al demandante la carga procesal de impulsar el tr\u00e1mite \u00a0 judicial, las normas recogidas en la Constituci\u00f3n Pol\u00edtica han transformado la \u00a0 manera de entender el car\u00e1cter rogado de la jurisdicci\u00f3n administrativa, en el \u00a0 sentido de que, a partir de la Carta Fundamental, se reafirma el principio de \u00a0 supremac\u00eda de la Constituci\u00f3n sobre el resto de normas del ordenamiento jur\u00eddico \u00a0 y la prevalencia del derecho sustancial sobre lo meramente adjetivo. \u00a0 \u00a0<\/p>\n<p>6.1.6. Asimismo, el Consejo de Estado ha expresado que el juez \u00a0 administrativo est\u00e1 en el deber de interpretar la relaci\u00f3n jur\u00eddico procesal \u00a0 trabada por las partes y no simplemente aplicar el principio de justicia rogada \u00a0 cuando: (i) la falta de t\u00e9cnica jur\u00eddica le impide comprender con \u00a0 suficiencia algunos de los presupuestos relevantes que orientan su labor en el \u00a0 proceso[86]; (ii) la aplicaci\u00f3n estricta de este principio \u00a0 desconozca normas o principios consagrados en la Constituci\u00f3n Pol\u00edtica; (iii) \u00a0deje por fuera el cumplimiento de compromisos asumidos por el Estado \u00a0 colombiano en materia de derechos humanos e infracciones al derecho \u00a0 internacional humanitario y, por \u00faltimo, (iv) en la resoluci\u00f3n del caso \u00a0 concreto, aun aplic\u00e1ndose normas procesales pertinentes, se ignoran otras \u00a0 disposiciones jur\u00eddicas relevantes para la adopci\u00f3n de una adecuada decisi\u00f3n[87]. \u00a0 \u00a0<\/p>\n<p>6.1.7. En \u00a0 conclusi\u00f3n, de conformidad con los par\u00e1metros expuestos con anterioridad, esta \u00a0 Corporaci\u00f3n reitera que, por regla general, resulta legal y jurisprudencialmente \u00a0 v\u00e1lido que el juez de alzada se pronuncie \u00fanicamente sobre los reparos \u00a0 formulados por los apelantes, pues son las partes las que tienen la carga \u00a0 procesal de exponer las razones por las cuales consideran que la decisi\u00f3n \u00a0 judicial resulta contraria a sus derechos e intereses. No obstante lo anterior, \u00a0 la aplicaci\u00f3n del principio de justicia rogada, en materia de lo contencioso \u00a0 administrativo, no puede llegar al extremo de conducir a la adopci\u00f3n de una \u00a0 decisi\u00f3n judicial que resulte abiertamente incompatible con el ordenamiento \u00a0 jur\u00eddico, especialmente cuando su interpretaci\u00f3n restringe (i) el goce \u00a0 efectivo de los derechos fundamentales de aplicaci\u00f3n inmediata previstos en el \u00a0 Texto Superior, (ii) normas y principios consagrados en la Constituci\u00f3n \u00a0 Pol\u00edtica, (iii) la real comprensi\u00f3n de la relaci\u00f3n jur\u00eddica-procesal \u00a0 trabada por las partes, (iv) el cumplimiento de derechos humanos y normas \u00a0 de derecho internacional humanitario ratificadas por el Estado colombiano y, \u00a0 finalmente, \u00a0(v) leyes relevantes para la resoluci\u00f3n del asunto comprometido. \u00a0 \u00a0 \u00a0<\/p>\n<p>6.2. Acci\u00f3n de \u00a0 reparaci\u00f3n directa. Fundamento constitucional y finalidad \u00a0 \u00a0<\/p>\n<p>6.2.1. La \u00a0 acci\u00f3n de reparaci\u00f3n directa es una de las v\u00edas jurisdiccionales previstas por \u00a0 el Legislador para solicitar la declaratoria de responsabilidad del Estado a \u00a0 causa de la ocurrencia de un da\u00f1o antijur\u00eddico producido por uno de sus agentes. \u00a0 \u00a0<\/p>\n<p>6.2.2. A partir de la \u00a0 Carta Pol\u00edtica de 1991, la acci\u00f3n de reparaci\u00f3n directa, as\u00ed como el resto de \u00a0 mecanismos jurisdiccionales de control a la Administraci\u00f3n, recibieron un \u00a0 fundamento constitucional expl\u00edcito. En tal sentido, el art\u00edculo 90 superior \u00a0 consagra que \u201cel Estado responder\u00e1 patrimonialmente por los da\u00f1os \u00a0 antijur\u00eddicos que le sean imputables, causados por la acci\u00f3n o la omisi\u00f3n de las \u00a0 autoridades p\u00fablicas\u201d. \u00a0 \u00a0<\/p>\n<p>En oportunidades anteriores, este mandato \u00a0 constitucional ha sido valorado por esta Corporaci\u00f3n, al examinar los cambios \u00a0 normativos introducidos al r\u00e9gimen de responsabilidad patrimonial del Estado. En \u00a0 particular, en las Sentencias C-333 de 1996[88], \u00a0 C-038 de 2006[89], C-644 \u00a0 de 2011[90] y T-339 \u00a0 de 2015[91], donde \u00a0 el Tribunal sostuvo que con el art\u00edculo 90 constitucional el sistema de \u00a0 responsabilidad estatal dejaba de fundamentarse en elementos conexos a la culpa \u00a0 de los agentes estatales, para soportarse en la antijuricidad del da\u00f1o, es \u00a0 decir, en las consecuencias jur\u00eddicas provocadas por el Estado que los \u00a0 particulares no estaban en el deber jur\u00eddico de soportar. En otras palabras, con la \u00a0 Constituci\u00f3n de 1991 se consagra una cl\u00e1usula general de responsabilidad, la \u00a0 cual comprende todos los da\u00f1os antijur\u00eddicos causados por las actuaciones u \u00a0 omisiones de las autoridades p\u00fablicas que se proyecta indistintamente del \u00a0 r\u00e9gimen aplicable a cada caso en particular. \u00a0 \u00a0<\/p>\n<p>6.2.3. \u00a0 Respecto de la acci\u00f3n de reparaci\u00f3n directa, en espec\u00edfico, este fundamento \u00a0 constitucional se hizo expl\u00edcito en la Ley 1437 de 2011 (actual C\u00f3digo de \u00a0 Procedimiento y de lo Contencioso Administrativo), al establecer que siguiendo \u00a0 el art\u00edculo 90 superior esta actuaci\u00f3n tendr\u00eda por finalidad asegurar que \u00a0 cualquier persona pueda demandar la reparaci\u00f3n del da\u00f1o antijur\u00eddico producido \u00a0 por las autoridades del Estado. Expresamente se\u00f1ala la norma que \u201cel Estado \u00a0 responder\u00e1, ente otras, cuando la causa del da\u00f1o sea un hecho, una omisi\u00f3n, una \u00a0 operaci\u00f3n administrativa o la ocupaci\u00f3n temporal o permanente de inmueble por \u00a0 causa de trabajos p\u00fablicos o por cualquiera otra causa imputable a una entidad \u00a0 p\u00fablica o a un particular que haya obrado siguiendo una expresa instrucci\u00f3n de \u00a0 la misma\u201d. \u00a0 \u00a0<\/p>\n<p>6.2.4. Bajo este \u00a0 entendimiento, el Consejo de Estado ha construido una doctrina jurisprudencial \u00a0 en relaci\u00f3n con la acci\u00f3n de reparaci\u00f3n directa, en la que no solo ha precisado \u00a0 las modalidades que se derivan de este mecanismo jurisdiccional, sino que adem\u00e1s \u00a0 ha desarrollado los diversos tipos de responsabilidad extracontractual y \u00a0 reg\u00edmenes presentes en cada caso, como ocurre con los da\u00f1os antijur\u00eddicos \u00a0 soportados por conscriptos, que fue objeto de examen por la Secci\u00f3n Tercera del \u00a0 Consejo de Estado en el proceso que ahora se demanda. Para ejemplificar lo anterior, en la Sentencia del 11 de abril de \u00a0 2016, la Secci\u00f3n Tercera del Consejo de Estado expres\u00f3 que bastaba demostrar la \u00a0 ocurrencia del da\u00f1o antijur\u00eddico y su relaci\u00f3n de causalidad con la actuaci\u00f3n de \u00a0 la Administraci\u00f3n para reconocer la indemnizaci\u00f3n a las v\u00edctimas. As\u00ed, el da\u00f1o \u00a0 antijur\u00eddico \u201cconsistir\u00e1 siempre en la lesi\u00f3n patrimonial o extra-patrimonial \u00a0 que la v\u00edctima no est\u00e1 en el deber jur\u00eddico de \u00a0 soportar. En este sentido, el da\u00f1o ocasionado a un bien jur\u00eddicamente tutelado, \u00a0 impone el deber de indemnizar el consecuente detrimento con el objetivo de \u00a0 garantizar el principio de igualdad ante las cargas p\u00fablicas\u201d. \u00a0 \u00a0<\/p>\n<p>6.2.5. En un \u00a0 sentido similar, la Corte Constitucional ha sostenido que el prop\u00f3sito de la \u00a0 acci\u00f3n de la acci\u00f3n de reparaci\u00f3n directa es que \u201cla persona que se crea lesionada o \u00a0 afectada (\u2026) pueda solicitar directamente ante la jurisdicci\u00f3n de lo contencioso \u00a0 administrativo que se repare el da\u00f1o causado y se le reconozcan las dem\u00e1s \u00a0 indemnizaciones que correspondan, esto es, sin reclamaci\u00f3n previa a la \u00a0 administraci\u00f3n o mediando petici\u00f3n de nulidad, como en el caso de la acci\u00f3n de \u00a0 restablecimiento del derecho. Se trata de una t\u00edpica acci\u00f3n tendiente a \u00a0 indemnizar a las personas con ocasi\u00f3n de la responsabilidad extracontractual en \u00a0 que pudo incurrir el Estado, en raz\u00f3n de las actividades anteriormente \u00a0 indicadas, que excluyen de entrada el acto administrativo\u201d[92]. \u00a0 \u00a0<\/p>\n<p>6.2.6. Con \u00a0 relaci\u00f3n a esto \u00faltimo, adicionalmente, vale la pena precisar que en el caso de \u00a0 los miembros de la Fuerza P\u00fablica que sufrieron da\u00f1os en el marco del conflicto \u00a0 armado, por actuaciones contrarias al derecho internacional humanitario y los \u00a0 derechos humanos, el ordenamiento jur\u00eddico ha reconocido su calidad de v\u00edctimas \u00a0 directas del conflicto armado y, por consiguiente, la jurisprudencia de esta \u00a0 Corporaci\u00f3n ha establecido, en vista de esta condici\u00f3n, una protecci\u00f3n \u00a0 constitucional reforzada que se ve reflejada, entre otros aspectos, en un \u00a0 tratamiento especial en materia indemnizatoria, derivada de su relaci\u00f3n con el \u00a0 Estado y de la actividad peligrosa que desarrollan. \u00a0Al \u00a0 respecto, basta con se\u00f1alar que en la Sentencia C-161 de 2016 est\u00e1 Corporaci\u00f3n \u00a0 dej\u00f3 claro que \u201cel reconocimiento de la condici\u00f3n de v\u00edctimas de los \u00a0 integrantes de la Fuerza P\u00fablica por hechos relacionados con el conflicto armado \u00a0 interno, cuenta con una importante tradici\u00f3n en el orden jur\u00eddico colombiano y \u00a0 en la jurisprudencia relativa a contextos normativos tanto de justicia \u00a0 transicional como de ordinaria. No obstante, dicho reconocimiento va asociado a \u00a0 un tratamiento especial en materia indemnizatoria, derivado de la existencia de \u00a0 una relaci\u00f3n laboral con el Estado voluntariamente asumida, de los riesgos \u00a0 previamente valorados que entra\u00f1a la actividad adscrita a ese v\u00ednculo laboral, y \u00a0 de los derechos legales y reglamentarios que se concretan cuando ocurre un da\u00f1o \u00a0 vinculado a esa actividad ordinaria de riesgo, propio de su labor\u201d. \u00a0 \u00a0<\/p>\n<p>6.2.7. En \u00a0 consecuencia, se concluye que la acci\u00f3n de reparaci\u00f3n directa, como su propio \u00a0 nombre lo indica, tiene por finalidad proteger la posici\u00f3n jur\u00eddica de las \u00a0 v\u00edctimas, es decir, de las personas que vieron lesionados sus intereses y derechos como resultado de \u201cun \u00a0 hecho, una omisi\u00f3n, una operaci\u00f3n administrativa o la ocupaci\u00f3n temporal o \u00a0 permanente del inmueble por causa de trabajos p\u00fablicos\u201d[93], as\u00ed como sucede con los miembros de la \u00a0 Fuerza P\u00fablica que sufrieron da\u00f1os en el marco del conflicto armado y que, como \u00a0 se indic\u00f3 con anterioridad, ha sido reforzada por la cl\u00e1usula general de \u00a0 responsabilidad prevista en la Constituci\u00f3n de 1991 y la jurisprudencia del juez \u00a0 especializado en la materia. \u00a0 \u00a0<\/p>\n<p>III. SOLUCI\u00d3N AL CASO CONCRETO \u00a0 \u00a0<\/p>\n<p>7.1. La presente \u00a0 acci\u00f3n de tutela se origina por la decisi\u00f3n adoptada por la Subsecci\u00f3n A de la \u00a0 Secci\u00f3n Tercera del Consejo de Estado, en el sentido de negar el reconocimiento \u00a0 de perjuicios a los accionantes en el presente proceso de tutela, aun cuando \u00a0 declar\u00f3 administrativa y patrimonialmente responsable a la Naci\u00f3n por el \u00a0 secuestro del que fueron v\u00edctimas directas, bajo el argumento de que los efectos \u00a0 de la sentencia \u00fanicamente cubren a los demandantes que estaban representados \u00a0 por el abogado que impugn\u00f3 la sentencia de primera instancia, a saber, las \u00a0 v\u00edctimas indirectas y hermanos de los tutelantes. Por consiguiente, comoquiera \u00a0 que la apoderada voluntariamente reconocida por los actores no apel\u00f3 la \u00a0 providencia en menci\u00f3n, no le era legalmente admisible al fallador pronunciarse \u00a0 sobre sus pretensiones. \u00a0 \u00a0<\/p>\n<p>El debate planteado por los accionantes y \u00a0 examinado por los jueces de instancia no se redujo a determinar cu\u00e1l apoderado \u00a0 gozaba de legitimidad para representar los intereses en pugna, sino que m\u00e1s all\u00e1 \u00a0 de la valoraci\u00f3n acerca del alcance del mandato judicial, desde una perspectiva \u00a0 constitucional, la controversia gir\u00f3 en torno a c\u00f3mo deb\u00edan aplicarse las \u00a0 disposiciones que establecen el tr\u00e1mite del recurso de alzada en la jurisdicci\u00f3n \u00a0 de lo contencioso administrativo, en el caso espec\u00edfico de los tutelantes, \u00a0 quienes alegaron la vulneraci\u00f3n de derechos sustanciales de rango constitucional \u00a0 y legal. \u00a0 \u00a0<\/p>\n<p>Como se explic\u00f3 en los antecedentes de la \u00a0 tutela, para la parte actora la sentencia proferida por el Consejo de Estado \u00a0 quebrant\u00f3 sus derechos fundamentales al exigirse, bajo una mirada estricta, la \u00a0 carga procesal de impugnar la decisi\u00f3n de primera instancia, sin tener en cuenta \u00a0 las condiciones f\u00e1cticas y jur\u00eddicas del caso: (i) la calidad de v\u00edctimas \u00a0 directas del conflicto armado, en su condici\u00f3n de miembros de la fuerza p\u00fablica \u00a0 en servicio activo; (ii) la falta de diligencia de la apoderada de los \u00a0 actores, en ejercicio de los mecanismos de defensa; (iii) el hecho de \u00a0 que, en todo caso, la sentencia de primera instancia fue impugnada por el \u00a0 apoderado inicial, ratificado en el curso del recurso de apelaci\u00f3n; (iv) \u00a0 la satisfacci\u00f3n del derecho a la reparaci\u00f3n por el da\u00f1o antijur\u00eddico soportado; \u00a0 (v) \u00a0el requerimiento de justicia frente al secuestro y, finalmente, (vi) \u00a0 el reconocimiento de la verdad objetiva de los hechos que, incluso, fue \u00a0 declarada por el propio juzgador. \u00a0 \u00a0<\/p>\n<p>Para la parte demandada y los jueces de \u00a0 instancia, el Consejo de Estado procedi\u00f3 de conformidad con las reglas previstas \u00a0 en el ordenamiento jur\u00eddico, las cuales lo obligaban a examinar, en estricto \u00a0 sentido, los reparos que fueron formulados por el apoderado de las v\u00edctimas \u00a0 indirectas. Por consiguiente, sostuvieron que los accionantes no pueden \u00a0 beneficiarse de las actuaciones desplegadas por su antiguo abogado y, menos a\u00fan, \u00a0 imput\u00e1rsele al ejercicio jurisdiccional la omisi\u00f3n en que incurri\u00f3 la apoderada \u00a0 judicial libremente designada por los demandantes. \u00a0 \u00a0<\/p>\n<p>7.2. A la luz de este \u00a0 debate y de las reglas que han sido expuestas ut supra, comparte la Corte \u00a0 Constitucional la posici\u00f3n de la parte accionante, en el sentido de considerar \u00a0 que el Consejo de Estado incurri\u00f3 en los defectos procedimental y sustantivo al \u00a0 adoptar, en el tr\u00e1mite del recurso de apelaci\u00f3n, la Sentencia del 27 de abril de \u00a0 2016, excluyendo de sus efectos el reconocimiento judicial de perjuicios a los \u00a0 aqu\u00ed demandantes, por cuanto es claro que en dicha sentencia se resolvi\u00f3 sobre \u00a0 el fondo del asunto del que depend\u00eda el derecho a la reparaci\u00f3n de los aqu\u00ed \u00a0 accionantes y la omisi\u00f3n de pronunciarse sobre el mismo es atribuible a una \u00a0 actuaci\u00f3n que privilegi\u00f3 lo formal sobre lo sustantivo. \u00a0 \u00a0<\/p>\n<p>7.3. En este caso \u00a0 espec\u00edfico, el defecto procedimental por exceso ritual manifiesto no se produjo \u00a0 por la decisi\u00f3n del Consejo de Estado de delimitar su competencia a los cargos \u00a0 esgrimidos por los apelantes, pues la Corte entiende que tal proceder \u00a0 materializa el car\u00e1cter rogado de la jurisdicci\u00f3n administrativa, sino por el \u00a0 hecho de que, al limitar el alcance de su pronunciamiento, sin considerar las \u00a0 circunstancias particulares que rodearon el caso, su decisi\u00f3n quebrant\u00f3 el \u00a0 mandato constitucional de darle prevalencia a lo sustancial sobre lo adjetivo \u00a0 contenido en el art\u00edculo 228 Superior. Lo anterior por cuanto: \u00a0 \u00a0<\/p>\n<p>(i) Seg\u00fan se \u00a0 desprende del expediente de tutela, desde la presentaci\u00f3n del recurso de \u00a0 apelaci\u00f3n por parte del abogado judicialmente reconocido en el tr\u00e1mite de la \u00a0 acci\u00f3n de reparaci\u00f3n directa, qued\u00f3 habilitada la competencia del Consejo de \u00a0 Estado para definir la situaci\u00f3n jur\u00eddica de los accionantes, en tanto el \u00a0 an\u00e1lisis de la responsabilidad de la Naci\u00f3n por los hechos ocurridos en el a\u00f1o \u00a0 1998, cuando aquellos prestaban el servicio militar obligatorio, no era un \u00a0 elemento adicional del debate del recurso de apelaci\u00f3n, sino que representaba, \u00a0 en estricto sentido, el t\u00f3pico de la controversia. De modo que, la condici\u00f3n de \u00a0 la que depende la pretensi\u00f3n de los accionantes no era un aspecto que se \u00a0 encontrase sustra\u00eddo del debate y sobre el cual pudiese decirse\u00a0 que no se \u00a0 hab\u00eda activado la competencia del Consejo de Estado para pronunciarse en sede de \u00a0 apelaci\u00f3n. \u00a0 \u00a0 \u00a0<\/p>\n<p>Como se advierte de la lectura de los \u00a0 antecedentes, el Tribunal Administrativo del Meta, A quo en la causa que \u00a0 se analiza, deneg\u00f3 las pretensiones de la demanda de reparaci\u00f3n directa, \u00a0 argumentando la falta de demostraci\u00f3n de la actuaci\u00f3n negligente por parte del \u00a0 Ej\u00e9rcito Nacional y el Ministerio de Defensa. Tal determinaci\u00f3n fue objeto de \u00a0 recurso de apelaci\u00f3n, de modo que, al Consejo de Estado, autoridad designada \u00a0 para resolver el recurso de apelaci\u00f3n, le correspond\u00eda determinar si realmente \u00a0 se configur\u00f3 el da\u00f1o antijur\u00eddico sobre los tutelantes, en su condici\u00f3n de \u00a0 v\u00edctimas directas, as\u00ed como el grado de conexidad entre el da\u00f1o y la prestaci\u00f3n \u00a0 del servicio militar que efectuaron en el a\u00f1o 1998. En este contexto, era \u00a0 razonable considerar que la Corporaci\u00f3n judicial que ten\u00eda la competencia para \u00a0 decidir de fondo el asunto, que involucraba en s\u00ed mismo un pronunciamiento \u00a0 respecto de la situaci\u00f3n jur\u00eddica de los accionantes, decidiera acerca de los \u00a0 planteamientos y pretensiones que fueron formuladas por \u00e9stos al trabarse la \u00a0 relaci\u00f3n jur\u00eddico-procesal, lo cual inclu\u00eda su derecho a la reparaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>El anterior razonamiento no puede \u00a0 conducir a pensar que esta Corporaci\u00f3n pretende modificar las reglas relativas \u00a0 al car\u00e1cter rogado de la jurisdicci\u00f3n administrativa, de manera que el Consejo \u00a0 de Estado se vea obligado a asumir el conocimiento oficioso de toda la \u00a0 controversia judicial, sin que sea necesario la presentaci\u00f3n del recurso de \u00a0 apelaci\u00f3n. As\u00ed, es claro que pueden plantearse escenarios f\u00e1cticos en los \u00a0 cuales, por v\u00eda de ejemplo, ninguna de las partes haya impugnado la decisi\u00f3n de \u00a0 primera instancia o en los que\u00a0 el cargo esgrimido por el apelante \u00fanico se \u00a0 hubiese reducido a un aspecto espec\u00edfico de la controversia judicial, que solo \u00a0 le interesaba al mismo y que, por ende, limitaba el \u00e1mbito de competencia del \u00a0 tribunal el cual quedaba inhabilitado para pronunciarse sobre otros elementos \u00a0 del juicio. Esta consideraci\u00f3n solamente pretende enfatizar en que, en vista de \u00a0 las circunstancias espec\u00edficas del caso y habilitada la competencia de la \u00a0 Corporaci\u00f3n demandada para decidir, justamente, acerca de la responsabilidad \u00a0 patrimonial y administrativa de la Naci\u00f3n por el hechos acaecidos sobre los \u00a0 tutelantes, en su condici\u00f3n de v\u00edctimas directas, no era posible excluirlos de \u00a0 las \u00f3rdenes de la decisi\u00f3n, \u00fanicamente, bajo el aparente incumplimiento de una \u00a0 regla adjetiva. \u00a0 \u00a0<\/p>\n<p>(ii) En el mismo \u00a0 sentido, se estima que resulta contrario al principio constitucional de darle \u00a0 prevalencia a lo sustancial sobre las formas, que aun cuando las circunstancias \u00a0 particulares del caso le permitieron al Consejo de Estado, mediante la sentencia \u00a0 controvertida, se\u00f1alar que los demandantes acreditaron todos los presupuestos \u00a0 sustanciales necesarios para declarar la responsabilidad patrimonial y \u00a0 administrativa de la Naci\u00f3n, \u00fanicamente, bajo la consideraci\u00f3n de que la nueva \u00a0 apoderada no impugn\u00f3 la decisi\u00f3n judicial, las v\u00edctimas directas fueran \u00a0 excluidas del reconocimiento de perjuicios por los da\u00f1os que, de hecho, ellos \u00a0 sufrieron y, por los cuales, fue condenada la Naci\u00f3n. Dicho de otro modo, \u00a0 habilitada la competencia del Consejo de Estado, a trav\u00e9s del recurso de \u00a0 apelaci\u00f3n presentado por el abogado de las v\u00edctimas indirectas, no resulta \u00a0 constitucionalmente admisible que el fallador acreditara \u201cla existencia del \u00a0 hecho da\u00f1oso, as\u00ed como el nexo causal entre \u00e9ste y la prestaci\u00f3n del servicio \u00a0 militar obligatorio\u201d[94] y, \u00a0 adicionalmente, declarara \u201cadministrativa y patrimonialmente responsable a la \u00a0 Naci\u00f3n por los da\u00f1os ocasionados a la parte actora\u201d[95], \u00a0 pero, con fundamento en una regla procedimental, dejara de reconocer la \u00a0 indemnizaci\u00f3n de perjuicios a las v\u00edctimas directas del hecho que sirvi\u00f3 de \u00a0 fundamento para revocar la decisi\u00f3n del A quo. \u00a0 \u00a0<\/p>\n<p>As\u00ed visto, desde el momento que la \u00a0 Corporaci\u00f3n demandada privilegi\u00f3, en t\u00e9rminos estrictos, la carga procesal de \u00a0 impugnar la decisi\u00f3n de primera instancia sobre los presupuestos sustanciales \u00a0 que se demostraron en el curso de la acci\u00f3n de reparaci\u00f3n directa, la Sentencia \u00a0 del 26 de abril de 2017, en lo que corresponde a los aqu\u00ed accionantes, result\u00f3 \u00a0 incompatible con derechos sustanciales, de rango constitucional y legal, como \u00a0 sucede con el derecho que tienen todas las v\u00edctimas del conflicto armado, \u00a0 particularmente las directas, a la reparaci\u00f3n por los da\u00f1os antijur\u00eddicos \u00a0 soportados. De hecho, esta Corte estima que la decisi\u00f3n adoptada por el Consejo \u00a0 de Estado, analizada en el caso espec\u00edfico, no solo implic\u00f3 un fallo \u00a0 incongruente entre la parte motiva de la providencia, que declar\u00f3 la \u00a0 responsabilidad de la Naci\u00f3n por los da\u00f1os que padecieron durante el secuestro, \u00a0 y la parte resolutiva, que los excluy\u00f3 de la indemnizaci\u00f3n de perjuicios, sino \u00a0 que adem\u00e1s provoc\u00f3, sin justificaci\u00f3n v\u00e1lida, un tratamiento desigual entre las \u00a0 v\u00edctimas directas e indirectas, bajo la \u00fanica consideraci\u00f3n de que la apoderada \u00a0 judicial de los primeros no present\u00f3 el respectivo recurso de apelaci\u00f3n, no \u00a0 obstante que, como se ver\u00e1 continuaci\u00f3n hab\u00eda alternativas hermen\u00e9uticas sobre \u00a0 este aspecto procesal que habr\u00edan permitido una soluci\u00f3n distinta. \u00a0 \u00a0<\/p>\n<p>Al margen del debate interpretativo que \u00a0 pueda generarse del art\u00edculo 69 del C\u00f3digo de Procedimiento Civil, que fija las \u00a0 reglas para la terminaci\u00f3n del poder, aplicables a este caso, lo cierto fue que\u00a0 \u00a0 ni el Tribunal Administrativo del Meta, ni el Consejo de Estado, se pronunciaron \u00a0 de forma oportuna sobre la designaci\u00f3n de la nueva apoderada judicial o la \u00a0 revocatoria del poder al abogado inicial, como para imput\u00e1rsele a los \u00a0 accionantes toda la responsabilidad de las circunstancias que ponen en duda el \u00a0 real alcance del recurso de apelaci\u00f3n presentado en el proceso judicial de la \u00a0 referencia. De este modo, al existir ciertas circunstancias f\u00e1cticas \u00a0 excepcionales, era v\u00e1lido suponer que el Ad quem valorar\u00eda con un alcance \u00a0 m\u00e1s amplio la impugnaci\u00f3n formulada respecto de todos los demandantes, en \u00a0 especial, teniendo en cuenta que: \u00a0 \u00a0 \u00a0<\/p>\n<p>(i) En el curso de la \u00a0 acci\u00f3n de reparaci\u00f3n directa \u00fanicamente se le reconoci\u00f3 expresa personer\u00eda \u00a0 jur\u00eddica al abogado inicial, designado por todos los demandantes para presentar \u00a0 y llevar hasta su culminaci\u00f3n el tr\u00e1mite de responsabilidad estatal. \u00a0 \u00a0<\/p>\n<p>(ii) La nueva \u00a0 apoderada judicial designada por los aqu\u00ed accionantes nunca compareci\u00f3 al \u00a0 proceso, ni tampoco las autoridades judiciales involucradas en el tr\u00e1mite de la \u00a0 acci\u00f3n de reparaci\u00f3n directa le reconocieron, de forma expresa, su personer\u00eda \u00a0 jur\u00eddica. En contraste, el abogado inicial, judicialmente reconocido, continu\u00f3 \u00a0 representando a todas las v\u00edctimas, mediante la radicaci\u00f3n, en t\u00e9rmino, de las \u00a0 actuaciones necesarias para avanzar en el desarrollo del proceso, al punto que \u00a0 alleg\u00f3 el recurso de apelaci\u00f3n a favor de todos los demandantes, continu\u00f3 \u00a0 ejerciendo las facultades previstas en el art\u00edculo 70 del C\u00f3digo de \u00a0 Procedimiento Civil, inclusive, en el tr\u00e1mite de segunda instancia, aport\u00f3 los \u00a0 respectivos alegatos en representaci\u00f3n de las v\u00edctimas directas e indirectas. De \u00a0 modo que, para hacer efectiva la prohibici\u00f3n de que no pueden actuar, en un \u00a0 mismo proceso, dos apoderados judiciales en representaci\u00f3n de las mismas \u00a0 personas (66 C.P.C.), era menester que la nueva apoderada judicial hubiera \u00a0 ejercido realmente su mandato o, al menos, se aceptara expresamente su poder \u00a0 (art. 67 C.P.C), circunstancias que no acontecieron en el proceso que ahora se \u00a0 analiza. \u00a0 \u00a0<\/p>\n<p>(iii) De hecho, no hubo \u00a0 manifestaci\u00f3n expresa por parte del Tribunal Administrativo del Meta acerca del \u00a0 reconocimiento de la personer\u00eda jur\u00eddica de la nueva apoderada judicial, pese a \u00a0 que con posterioridad a la presentaci\u00f3n de la revocatoria del poder y el \u00a0 otorgamiento de uno nuevo, se profirieron distintas providencias judiciales, las \u00a0 cuales omitieron un pronunciamiento espec\u00edfico en la materia. Adem\u00e1s de la \u00a0 anterior omisi\u00f3n, el A quo concedi\u00f3 el recurso de apelaci\u00f3n interpuesto \u00a0 por el apoderado judicial a nombre de todos los demandantes, sin realizar \u00a0 ninguna precisi\u00f3n respecto de la legitimaci\u00f3n en la causa del abogado para \u00a0 representar los intereses de los aqu\u00ed accionantes. \u00a0 \u00a0<\/p>\n<p>(iv) Asimismo, el \u00a0 Consejo de Estado decidi\u00f3, mediante auto, admitir la impugnaci\u00f3n as\u00ed \u00a0 interpuesta, sin pronunciarse sobre la legitimidad del apoderado de los \u00a0 apelantes. Solamente cuando los tutelantes manifestaron ante la Corporaci\u00f3n las \u00a0 dificultades a las que se vieron avocados para solicitarle informaci\u00f3n a la \u00a0 nueva apoderada judicial y que, en \u00faltimas, los llevaron a la revocatoria de su \u00a0 poder, el Consejo de Estado se pronunci\u00f3 sobre el derecho de postulaci\u00f3n de las \u00a0 v\u00edctimas directas, sin oponerse a la ratificaci\u00f3n que estas hac\u00edan al abogado \u00a0 inicial. \u00a0 \u00a0<\/p>\n<p>En raz\u00f3n de las anteriores circunstancias \u00a0 espec\u00edficas que acontecieron en el curso de la acci\u00f3n de reparaci\u00f3n directa, \u00a0 esta Sala considera que, en este caso concreto, bajo la exigencia de satisfacer \u00a0 una carga procesal, no pod\u00eda desconocerse el principio de prevalencia de lo \u00a0 sustancial sobre lo formal, as\u00ed como el derecho a la reparaci\u00f3n \u2013en su contenido \u00a0 indemnizatorio- de miembros de la Fuerza P\u00fablica a los que el ordenamiento \u00a0 jur\u00eddico les ha reconocido la calidad de v\u00edctimas del conflicto armado y, en consecuencia, la protecci\u00f3n reforzada que por \u00a0 esta misma calidad ha previsto la jurisprudencia constitucional. Menos a\u00fan, que \u00a0 una interpretaci\u00f3n literal del car\u00e1cter rogado de la jurisdicci\u00f3n \u00a0 administrativa, representara la transgresi\u00f3n de derechos constitucionales, como \u00a0 a la igualdad, al debido proceso y al acceso a la administraci\u00f3n de justicia. \u00a0 \u00a0<\/p>\n<p>7.5. No obstante las \u00a0 anteriores consideraciones, la Corte Constitucional quiere dejar claro que las \u00a0 mismas no constituyen una nueva regla de interpretaci\u00f3n que le implique al juez \u00a0 de alzada valorar la situaci\u00f3n jur\u00eddica de todas las partes involucradas en el \u00a0 curso del proceso judicial de su competencia, sino que, como ya se indic\u00f3, en \u00a0 raz\u00f3n de las circunstancias muy particulares del caso (en especial, el hecho de \u00a0 que la competencia del Consejo de Estado qued\u00f3 habilitada, el t\u00f3pico de la \u00a0 discusi\u00f3n era la situaci\u00f3n jur\u00eddica de las v\u00edctimas directas, el cumplimiento de \u00a0 todos los presupuestos sustanciales para el reconocimiento de los perjuicios, \u00a0 como lo reconoci\u00f3 el propio Ad quem, y el papel desempe\u00f1ado por los \u00a0 apoderados judiciales) era razonable y jur\u00eddicamente v\u00e1lido que, en atenci\u00f3n al \u00a0 principio de supremac\u00eda de los sustancial sobre las formas, reconocerle a las \u00a0 v\u00edctimas directas del da\u00f1o antijur\u00eddico los perjuicios por las afectaciones que \u00a0 se pretend\u00edan reparar con la decisi\u00f3n judicial aqu\u00ed controvertida. \u00a0 \u00a0<\/p>\n<p>7.6. A partir de lo \u00a0 expuesto, la Sala Plena concluye que la autoridad judicial demandada incurri\u00f3 en \u00a0 los defectos procedimental y sustantivo que hacen procedente, de forma \u00a0 excepcional, la acci\u00f3n de tutela contra providencias judiciales. Por \u00a0 consiguiente, para \u00a0 garantizar la materializaci\u00f3n de los derechos constitucionales a la igualdad, al \u00a0 debido proceso y al acceso a la administraci\u00f3n de justicia, se dejar\u00e1 sin \u00a0 efectos el fallo del 27 de abril de 2016 proferido por la Secci\u00f3n Tercera, \u00a0 Subsecci\u00f3n A del Consejo de Estado, pero \u00fanicamente respecto de los aqu\u00ed \u00a0 accionantes. Para en su lugar, con fundamento en las consideraciones expuestas \u00a0 en la presente providencia, se proceda a reconocerles la indemnizaci\u00f3n de \u00a0 perjuicios en su calidad de v\u00edctimas directas del da\u00f1o antijur\u00eddico al que fue condenada la \u00a0 Naci\u00f3n, en vista de que, el Consejo de Estado ya se pronunci\u00f3 sobre la \u00a0 responsabilidad del Estado respecto de la situaci\u00f3n antijur\u00eddica de todos los \u00a0 demandantes, argumentando la acreditaci\u00f3n de todos los presupuestos sustanciales \u00a0 para el reconocimiento de la indemnizaci\u00f3n y la declaratoria de responsabilidad \u00a0 patrimonial y administrativa de la Naci\u00f3n. \u00a0 \u00a0<\/p>\n<p>IV. DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Corte Constitucional, administrando \u00a0 justicia en nombre del pueblo y por mandato de la Constituci\u00f3n, \u00a0 \u00a0<\/p>\n<p>RESUELVE \u00a0 \u00a0<\/p>\n<p>PRIMERO-. Levantar la suspensi\u00f3n de t\u00e9rminos decretada dentro del presente proceso de \u00a0 tutela. \u00a0 \u00a0<\/p>\n<p>SEGUNDO-. Por las razones expuestas en la \u00a0 providencia, \u00a0REVOCAR la sentencia de tutela proferida el 4 de octubre de 2018 por la \u00a0 Secci\u00f3n Quinta del Consejo \u00a0 de Estado, a trav\u00e9s de la cual se neg\u00f3 la acci\u00f3n de tutela de la referencia. En \u00a0 su lugar, CONCEDER a los se\u00f1ores H\u00e9ctor Enrique y Helbert Antonio Torres \u00a0 Tunjacipa el amparo de sus \u00a0 derechos constitucionales a la igualdad, al debido proceso y al acceso a la \u00a0 administraci\u00f3n de justicia. \u00a0 \u00a0<\/p>\n<p>TERCERO.- DEJAR SIN EFECTOS la Sentencia proferida el 27 de abril \u00a0 de 2016 por la Secci\u00f3n Tercera, Subsecci\u00f3n A del Consejo de Estado, por medio de \u00a0 la cual se declar\u00f3 administrativa y patrimonialmente responsable a la Naci\u00f3n \u00a0 (Ministerio de Defensa y Ej\u00e9rcito Nacional), pero \u00fanicamente respecto de la \u00a0 negativa a reconocerles la indemnizaci\u00f3n de perjuicios a los se\u00f1ores H\u00e9ctor \u00a0 Enrique y Helbert Antonio Torres Tunjacipa, para en su lugar, ordenarle a la \u00a0 misma autoridad judicial que, dentro de los 15 d\u00edas siguientes a la notificaci\u00f3n de esta providencia, ADICIONE el fallo referido con el reconocimiento de perjuicios a los \u00a0 accionantes, en su calidad de v\u00edctimas directas del da\u00f1o antijur\u00eddico al que fue \u00a0 condenada la Naci\u00f3n, seg\u00fan lo explicado en la presente sentencia. \u00a0 \u00a0<\/p>\n<p>CUARTO.- Por la Secretar\u00eda General de la Corte Constitucional, LIBRAR las \u00a0 comunicaciones respectivas, as\u00ed como DISPONER las notificaciones a las \u00a0 partes, previstas en el art\u00edculo 36 del Decreto Ley 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>C\u00f3piese, notif\u00edquese, comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>ALEJANDRO LINARES CANTILLO \u00a0 \u00a0<\/p>\n<p>Presidente \u00a0 \u00a0<\/p>\n<p>Con aclaraci\u00f3n de voto \u00a0 \u00a0<\/p>\n<p>GLORIA STELLA ORT\u00cdZ DELGADO \u00a0 \u00a0<\/p>\n<p>Magistrada \u00a0 \u00a0<\/p>\n<p>Con aclaraci\u00f3n de voto \u00a0 \u00a0<\/p>\n<p>LUIS GUILLERMO GUERRERO P\u00c9REZ \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>CARLOS LIBARDO BERNAL PULIDO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>Con aclaraci\u00f3n de voto \u00a0 \u00a0<\/p>\n<p>DIANA FAJARDO RIVERA \u00a0 \u00a0<\/p>\n<p>Impedida \u00a0 \u00a0<\/p>\n<p>ANTONIO JOS\u00c9 LIZARAZO OCAMPO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>Ausente \u00a0 \u00a0<\/p>\n<p>CRISTINA PARDO SCHLESINGER \u00a0 \u00a0<\/p>\n<p>Magistrada \u00a0 \u00a0<\/p>\n<p>JOS\u00c9 FERNANDO REYES CUARTAS \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>ALBERTO ROJAS R\u00cdOS \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>Ausente \u00a0 \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0 \u00a0<\/p>\n<p>Secretaria General \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>ACLARACION DE VOTO DEL MAGISTRADO \u00a0 \u00a0<\/p>\n<p>CARLOS BERNAL PULIDO \u00a0 \u00a0<\/p>\n<p>\u00a0A LA SENTENCIA SU061\/18 \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES EN PROCESO DE \u00a0 REPARACION DIRECTA-De manera general e injustificada se elimina la exigencia de la \u00a0 interposici\u00f3n del recurso de apelaci\u00f3n, lo que en la pr\u00e1ctica deroga las reglas \u00a0 de competencia de los jueces de segunda instancia, y afecta la seguridad \u00a0 jur\u00eddica (Aclaraci\u00f3n de voto) \u00a0 \u00a0<\/p>\n<p>Expediente: T.6.466.259 \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 Ponente: \u00a0 \u00a0<\/p>\n<p>LUIS GUILLERMO \u00a0 GUERRERO P\u00c9REZ \u00a0 \u00a0<\/p>\n<p>En atenci\u00f3n a la decisi\u00f3n adoptada por la Sala Plena el 7 de junio de 2018, \u00a0 presento Aclaraci\u00f3n de Voto a su fundamentaci\u00f3n respecto de la aplicaci\u00f3n del \u00a0 principio de prevalencia del derecho sustancial al tr\u00e1mite del recurso de \u00a0 apelaci\u00f3n contra las sentencias de reparaci\u00f3n directa proferidas por la \u00a0 jurisdicci\u00f3n de lo contencioso administrativo. \u00a0 \u00a0<\/p>\n<p>Esto por cuanto la sentencia \u00a0 sostiene que la interposici\u00f3n del recurso de apelaci\u00f3n, como requisito para \u00a0 habilitar la competencia del juez de segunda instancia, constituye una exigencia \u00a0 meramente formal que debe ceder ante la prevalencia del derecho sustancial, a \u00a0 fin de alcanzar la finalidad constitucional de la acci\u00f3n de reparaci\u00f3n directa. \u00a0 Considero equivocada esta tesis porque de manera general e injustificada elimina \u00a0 la exigencia de la interposici\u00f3n del recurso de apelaci\u00f3n en los procesos de \u00a0 reparaci\u00f3n directa, lo que en la pr\u00e1ctica deroga las reglas de competencia \u2013que \u00a0 son de orden p\u00fablico\u2013 de los jueces de segunda instancia en la jurisdicci\u00f3n de \u00a0 lo contencioso administrativo, y afecta la seguridad jur\u00eddica al soslayar el \u00a0 principio de cosa juzgada. \u00a0 \u00a0<\/p>\n<p>De otra parte, para resolver \u00a0 el litigio constitucional que le fue planteado a la Corte en esta oportunidad, \u00a0 no resultaba aplicable el antecedente jurisprudencial de la Sentencia T-398 de \u00a0 2017, porque el caso resuelto en aquella oportunidad por la Corte no presentaba \u00a0 similitud f\u00e1ctica alguna con el caso revisado en este proceso de tutela, lo que \u00a0 imped\u00eda realizar la correspondiente subsunci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Fecha ut supra \u00a0 \u00a0<\/p>\n<p>CARLOS BERNAL PULIDO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>ACLARACI\u00d3N DE \u00a0 VOTO DE LA MAGISTRADA \u00a0 \u00a0<\/p>\n<p>GLORIA STELLA ORTIZ DELGADO \u00a0 \u00a0<\/p>\n<p>A LA SENTENCIA SU.061\/18 \u00a0 \u00a0<\/p>\n<p>Referencia: Expediente T-6.466.259 \u00a0 \u00a0<\/p>\n<p>Acci\u00f3n de tutela presentada por H\u00e9ctor Enrique y Helbert \u00a0 Antonio Torres Tunjacipa en contra del Tribunal Administrativo del Meta y del \u00a0 Consejo de Estado, Secci\u00f3n Tercera, Subsecci\u00f3n A. \u00a0 \u00a0<\/p>\n<p>Magistrado sustanciador: \u00a0 \u00a0<\/p>\n<p>LUIS GUILLERMO GUERRERO P\u00c9REZ \u00a0 \u00a0<\/p>\n<p>Con el \u00a0 acostumbrado respeto por las decisiones de la Corte Constitucional, a \u00a0 continuaci\u00f3n presento la raz\u00f3n que me conduce a aclarar el voto en la \u00a0 sentencia SU-061 de 2018, adoptada por la mayor\u00eda de la Sala Plena, en \u00a0 sesi\u00f3n del 7 de junio de ese mismo a\u00f1o. \u00a0 \u00a0<\/p>\n<p>1. Al respecto, \u00a0 quiero manifestar que estoy de acuerdo con la decisi\u00f3n adoptada en la sentencia \u00a0 en comento, en el sentido de conceder el amparo de los derechos fundamentales de \u00a0 los accionantes y dejar sin efectos la parte de la sentencia proferida por el \u00a0 Consejo de Estado que neg\u00f3 la indemnizaci\u00f3n de perjuicios a las v\u00edctimas \u00a0 directas del da\u00f1o antijur\u00eddico que se encontr\u00f3 responsable al Estado. Sin \u00a0 embargo, debo puntualizar mi posici\u00f3n en relaci\u00f3n con una providencia que fue \u00a0 citada en el fallo para exponer el car\u00e1cter rogado de la jurisdicci\u00f3n \u00a0 contencioso administrativa, esto es, la Sentencia T-398 de 2017[96]. \u00a0 \u00a0<\/p>\n<p>2. En la \u00a0 Sentencia SU-061 de 2018, la Sala Plena concedi\u00f3 el amparo de los derechos a la \u00a0 igualdad, al debido proceso y al acceso a la administraci\u00f3n de justicia de dos \u00a0 miembros de la fuerza p\u00fablica a quienes se hab\u00eda negado por parte de la Secci\u00f3n \u00a0 Tercera del Consejo de Estado, el reconocimiento de perjuicios econ\u00f3micos y \u00a0 morales, aun cuando declar\u00f3 administrativa y patrimonialmente responsable a la \u00a0 Naci\u00f3n, por el secuestro de que ellos fueron v\u00edctimas directas, bajo el \u00a0 argumento de que los efectos de la sentencia \u00fanicamente cubr\u00edan a los \u00a0 demandantes que estaban representados por el apoderado que impugn\u00f3 la decisi\u00f3n \u00a0 judicial, esto es, a los hermanos de los accionantes, en la calidad de v\u00edctimas \u00a0 indirectas. Dicho en otras palabras, por un supuesto defecto t\u00e9cnico las \u00a0 personas secuestradas con responsabilidad del Estado, declarada por el \u00f3rgano de \u00a0 cierre de la jurisdicci\u00f3n contencioso administrativa, no tuvieron derecho a la \u00a0 reparaci\u00f3n, mientras que sus hermanos s\u00ed fueron reparados por ese secuestro. \u00a0 \u00a0<\/p>\n<p>La Sala Plena \u00a0 encontr\u00f3 que el Consejo de Estado incurri\u00f3 en un defecto de procedimiento por \u00a0 exceso ritual manifiesto, al desconocerse que la causa alegada conjuntamente por \u00a0 los accionantes y sus hermanos se present\u00f3 por el mismo apoderado judicial, \u00a0 quien posteriormente radic\u00f3 el recurso de apelaci\u00f3n sin distinguir su alcance \u00a0 entre los poderdantes. Por el contrario, el mismo apoderado solicit\u00f3 al ad \u00a0 quem incluir en el reconocimiento de los perjuicios a los accionantes. \u00a0 \u00a0<\/p>\n<p>3. Al \u00a0 pronunciarse sobre el car\u00e1cter rogado de la jurisdicci\u00f3n contencioso \u00a0 administrativa, la providencia aludi\u00f3 al antecedente jurisprudencial de la \u00a0 Sentencia T-398 de 2017, para explicar que este principio implica \u201cla imposibilidad del fallador para iniciar de oficio el \u00a0 tr\u00e1mite de apelaci\u00f3n, ya que son los sujetos procesales involucrados en la causa \u00a0 los que tienen el deber de sustentar los motivos de su inconformidad. As\u00ed visto, \u00a0 la competencia del juez de alzada se restringe a los cargos que fueron \u00a0 formulados por las partes a trav\u00e9s del recurso de apelaci\u00f3n\u201d[97]. \u00a0 \u00a0<\/p>\n<p>4. Con respecto a \u00a0 esa cita jurisprudencial, estimo conveniente precisar que el asunto analizado en \u00a0 esta oportunidad no guarda identidad f\u00e1ctica ni jur\u00eddica con el revisado \u00a0 en la Sentencia T-398 de 2017, tanto as\u00ed que en el tr\u00e1mite de nulidad de esa \u00a0 providencia, consider\u00e9 que deb\u00eda anularse el fallo proferido por la Sala S\u00e9ptima \u00a0 de Revisi\u00f3n, por haberse configurado la causal de \u00a0 desconocimiento del precedente judicial establecido por la Sala Plena de esta \u00a0 Corporaci\u00f3n, relacionada con el cumplimiento del requisito de subsidiariedad \u00a0 como causal gen\u00e9rica de procedencia de la acci\u00f3n de tutela contra providencias \u00a0 judiciales. Lo anterior, en tanto la accionante contaba con el recurso de \u00a0 apelaci\u00f3n para controvertir la decisi\u00f3n del juez de instancia que le fue \u00a0 adversa, el cual no fue presentado en la oportunidad procesal dispuesta para tal \u00a0 fin[98]. Luego, constitu\u00eda parte de la \u00a0 ratio decidendi de la sentencia T-398 de 2017, un asunto absolutamente ajeno \u00a0 al que ahora ocupaba la atenci\u00f3n de la Sala. \u00a0 \u00a0<\/p>\n<p>Al resolver el \u00a0 asunto, la Sala estim\u00f3 que a pesar de que proced\u00eda el recurso de apelaci\u00f3n \u00a0 contra la sentencia de primera instancia del proceso contencioso administrativo \u00a0 y \u00e9ste no fue agotado por la accionante de forma oportuna, se demostr\u00f3 una \u00a0 ausencia de defensa t\u00e9cnica. Asimismo, consider\u00f3 que el juez ordinario incurri\u00f3 \u00a0 en un defecto procedimental por exceso ritual manifiesto al otorgarle mayor \u00a0 relevancia a la omisi\u00f3n procesal de la accionante de no apelar la sentencia que \u00a0 a su condici\u00f3n de menor de edad y se limit\u00f3 a mantener un rol de juez pasivo que \u00a0 solo tiene competencia para conocer de los aspectos propuestos por los \u00a0 recurrentes en su apelaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>6. Conforme al \u00a0 anterior recuento\u00a0jurisprudencial, es evidente que el asunto resuelto en la \u00a0 Sentencia T-398 de 2017 no guarda identidad f\u00e1ctica ni jur\u00eddica con el caso \u00a0 resuelto en la providencia SU-061 de 2018, pues en este \u00faltimo los accionantes \u00a0 s\u00ed interpusieron el recurso de apelaci\u00f3n y, por ende, consider\u00e9 que la acci\u00f3n de \u00a0 tutela era procedente para proteger sus derechos constitucionales a la igualdad, al debido proceso y al acceso a la \u00a0 administraci\u00f3n de justicia, pues hab\u00edan superado el requisito de subsidiaridad. \u00a0 \u00a0<\/p>\n<p>De igual manera, considero que en la sentencia de 2017, uno de los aspectos \u00a0 relevantes para tomar la decisi\u00f3n constituy\u00f3 el hecho de que la accionante era \u00a0 una menor de edad, aspecto que no era predicable de los hechos objeto de estudio \u00a0 en el caso de la sentencia de 2018. En la sentencia que se consider\u00f3 precedente \u00a0 tambi\u00e9n se evalu\u00f3 la existencia de una deficiente defensa t\u00e9cnica, aspecto que \u00a0 tampoco involucraba el caso concreto en estudio. \u00a0 \u00a0<\/p>\n<p>Sin duda, esas diferencias muestran que en el caso de 2017, la Corte le exigi\u00f3 \u00a0 al juez contencioso administrativo que actuara en posici\u00f3n de parte para \u00a0 subsanar las deficiencias que presentaban la demanda y el proceso en general, \u00a0 mientras que en la sentencia SU-061 de 2018, el juez no ten\u00eda que desequilibrar \u00a0 el proceso hasta el punto de afectar el derecho de defensa de la parte \u00a0 demandada, sino que ten\u00eda que leer la impugnaci\u00f3n en el sentido en el que fue \u00a0 presentada por el apoderado de las v\u00edctimas directas y de ese modo garantizar \u00a0 los derechos fundamentales de los accionantes. Mientras que en el primer caso se \u00a0 exigi\u00f3 al juez contencioso administrativo fallar extra y ultrapetita \u00a0 (contrario al principio de justicia rogada que constituye una garant\u00eda de \u00a0 defensa en los procesos dispositivos), en el segundo caso se le recuerda al juez \u00a0 que, de conformidad con la ley, tiene facultades de interpretaci\u00f3n de los \u00a0 escritos que se presentan en el proceso contencioso administrativo. \u00a0 \u00a0<\/p>\n<p>7. En vista de que las dos sentencias conten\u00edan hechos, problemas \u00a0 constitucionales y fundamentos jur\u00eddicos distintos, no considero necesario \u00a0 apoyarse en la sentencia anterior como fundamento de este fallo. \u00a0 \u00a0<\/p>\n<p>De esta manera, \u00a0 expongo las razones que me conducen a aclarar el voto respecto de la \u00a0 sentencia SU-061 de 2018, adoptada por la Sala Plena de la Corte \u00a0 Constitucional. \u00a0 \u00a0<\/p>\n<p>Fecha \u00a0 ut supra, \u00a0 \u00a0<\/p>\n<p>GLORIA STELLA ORTIZ DELGADO \u00a0 \u00a0<\/p>\n<p>Magistrada \u00a0 \u00a0<\/p>\n<p>[1] En esta secci\u00f3n se relata los hechos descritos por \u00a0 los accionantes en la demanda de tutela, as\u00ed como los elementos f\u00e1cticos y \u00a0 jur\u00eddicos que obran en el expediente. \u00a0 \u00a0<\/p>\n<p>[2] Cuaderno principal expediente de tutela, folios \u00a0 40-41. Informaci\u00f3n consignada en la Sentencia proferida por la Secci\u00f3n Tercera \u00a0 del Consejo de Estado en el tr\u00e1mite de la acci\u00f3n de reparaci\u00f3n directa.\u00a0 \u00a0 \u00a0<\/p>\n<p>[3] Ib\u00eddem (Folios 167-174). \u00a0 \u00a0<\/p>\n<p>[4] Op. Cit. (Folio 176). \u00a0 \u00a0<\/p>\n<p>[5] Cuaderno principal expediente de tutela, folios \u00a0 20-34. \u00a0 \u00a0<\/p>\n<p>[6] Cuaderno principal expediente de tutela, folio 36. \u00a0 \u00a0<\/p>\n<p>[7] Seg\u00fan copia del proceso consignada en medio \u00a0 magn\u00e9tico. (Folio 46, parte 2). \u00a0 \u00a0<\/p>\n<p>[8] Ib\u00eddem (Folio 52, parte 2). \u00a0 \u00a0<\/p>\n<p>[9] Presentados los d\u00edas 12 de agosto de 2010 y 15 de \u00a0 noviembre de 2011. \u00a0 \u00a0<\/p>\n<p>[10] Op. cit. (Folio 178, parte 2). \u00a0 \u00a0<\/p>\n<p>[11] ib\u00eddem. (Folio 187, parte 2). \u00a0 \u00a0<\/p>\n<p>[12] Cuaderno principal expediente de tutela, folio 49. \u00a0 \u00a0<\/p>\n<p>[13] Cuaderno principal expediente de tutela, folio 47. \u00a0 \u00a0<\/p>\n<p>[14] Seg\u00fan copia del proceso consignada en medio \u00a0 magn\u00e9tico. (Folios 202-207, parte 2). \u00a0 \u00a0<\/p>\n<p>[15] Cuaderno principal expediente de tutela, folio 56. \u00a0 \u00a0<\/p>\n<p>[16] Auto del 29 de marzo de 2017. Cuaderno principal \u00a0 expediente de tutela, folio 58. \u00a0 \u00a0<\/p>\n<p>[17] Cuaderno principal expediente de tutela, folios \u00a0 133-134. \u00a0 \u00a0<\/p>\n<p>[19] La Secretar\u00eda General del Consejo de Estado efectu\u00f3 \u00a0 notificaci\u00f3n el 24 de julio de 2017. (Cuaderno principal expediente de tutela, \u00a0 folio 87).\u00a0 \u00a0 \u00a0<\/p>\n<p>[20] Igualmente, la Secretar\u00eda General del Consejo de \u00a0 Estado efectu\u00f3 las notificaciones al Ej\u00e9rcito Nacional y el Ministerio de \u00a0 Defensa, como partes interesadas en el resultado del proceso de tutela (Cuaderno \u00a0 principal expediente de tutela, folios 59 y 60).\u00a0 \u00a0 \u00a0<\/p>\n<p>[21] Como medio de prueba presentaron copia de la \u00a0 consulta del proceso de tutela, folio 98. \u00a0 \u00a0<\/p>\n<p>[22] Cuaderno principal expediente de tutela, folios \u00a0 99-111. \u00a0 \u00a0<\/p>\n<p>[23] Cuaderno principal expediente de tutela, folios \u00a0 18-40. \u00a0 \u00a0<\/p>\n<p>[24] Cuaderno principal expediente de tutela, folios \u00a0 41-52. \u00a0 \u00a0<\/p>\n<p>[25] \u00a0 Disco compacto que contiene dos archivos de 176 y 215 p\u00e1ginas. Cuaderno principal, \u00a0 folio 3. \u00a0 \u00a0<\/p>\n<p>[26] Cuaderno principal expediente de tutela, folios \u00a0 96-97. \u00a0 \u00a0<\/p>\n<p>[27] Cuaderno principal expediente de tutela, folio 98. \u00a0 \u00a0<\/p>\n<p>[28] Cuaderno principal expediente de tutela, folios \u00a0 101-112. \u00a0 \u00a0<\/p>\n<p>[29] Bajo un criterio objetivo \u00a0 orientador: \u201cla necesidad de pronunciarse sobre una determinada l\u00ednea \u00a0 jurisprudencial\u201d. \u00a0 \u00a0<\/p>\n<p>[30] El presente apartado sigue la l\u00ednea jurisprudencial \u00a0 definida en la Sentencia C-590 de 2005 y reiterada por el Magistrado Ponente en \u00a0 el fallo T-074 de 2018. \u00a0 \u00a0<\/p>\n<p>[31] Cfr., Corte Constitucional, Sentencias \u00a0 T-388 de 2006, T-590 de 2009, SU-817 de 2010, T-363 de 2011, SU-400 de 2012, \u00a0 SU-198 de 2013, SU-946 de 2014, SU-556 de 2015, SU-416 de 2015, C-086 de 2016, \u00a0 SU-490 de 2016, SU-210 de 2017, SU-355 de 2017 y SU-396 de 2017. \u00a0 \u00a0<\/p>\n<p>[32] Cfr., Corte Constitucional, Sentencias \u00a0 C-547 de 1992, T-590 de 2009, SU-946 de 2014, SU-817 de 2010 y SU-210 de 2017. \u00a0 \u00a0<\/p>\n<p>[33] Cfr., Corte Constitucional, Sentencias SU-556 de \u00a0 2015, SU-210 de 2017 y SU-537 de 2017. \u00a0 \u00a0<\/p>\n<p>[34] Cfr., Corte Constitucional, Sentencias \u00a0 T-114 de 2002 y T-136 de 2005. \u00a0 \u00a0<\/p>\n<p>[35] Cfr., Corte Constitucional, Sentencia \u00a0 T-586 de 2012. \u00a0 \u00a0<\/p>\n<p>[36] Cfr., Corte Constitucional, Sentencias \u00a0 C-590 de 2005, SU-817 de 2010, SU-400 de 2012 y SU-335 de 2017. \u00a0 \u00a0<\/p>\n<p>[37] Cfr., Corte Constitucional, Sentencias \u00a0 C-590 de 2005, T-388 de 2006, SU-946 de 2014 y SU-537 de 2017. \u00a0 \u00a0<\/p>\n<p>[38] Cfr., Corte Constitucional, Sentencia \u00a0 T-388 de 2006. \u00a0 \u00a0<\/p>\n<p>[39] Cfr., Corte Constitucional, Sentencias \u00a0 C-590 de 2005 y SU-537 de 2017. \u00a0 \u00a0<\/p>\n<p>[40] Cfr. Corte Constitucional, \u00a0 Sentencias C-590 de 2005, reiterado en los fallos T-936 de 2013, \u00a0 T-122 de 2017 y \u00a0 SU-537 de 2017, por citar algunos ejemplos. \u00a0 \u00a0<\/p>\n<p>[41] Cuaderno principal expediente de tutela, folio 56. \u00a0 \u00a0<\/p>\n<p>[42] Cfr., Corte Constitucional, Sentencia \u00a0 C-590 de 2005. \u00a0 \u00a0<\/p>\n<p>[43] Cfr., Corte Constitucional, Sentencias \u00a0 C-590 de 2005 y T-586 de 2012. \u00a0 \u00a0<\/p>\n<p>[44] Cfr., Corte Constitucional, Sentencia \u00a0 SU-537 de 2017. \u00a0 \u00a0<\/p>\n<p>[45] Cfr., Corte Constitucional, Sentencias \u00a0 C-590 de 2005 y SU-335 de 2017, \u00a0 \u00a0<\/p>\n<p>[46] Cfr., Corte Constitucional, Ib\u00eddem. \u00a0 \u00a0<\/p>\n<p>[47] Cfr. Corte Constitucional, Sentencia T-704 de 2012. \u00a0 \u00a0<\/p>\n<p>[48] Desde un inicio esta Corporaci\u00f3n manifest\u00f3, \u00a0 siguiendo las consideraciones efectuadas por la Corte Suprema de Justicia, que \u00a0 la actuaci\u00f3n judicial realizada por fuera del procedimiento previsto en la \u00a0 legislaci\u00f3n no solo era socialmente reprochable, sino que adem\u00e1s resultaba \u00a0 incompatible con los postulados fijados en la Carta Pol\u00edtica\u00a0 y, por lo \u00a0 tanto, la decisi\u00f3n deber\u00eda ser objeto de correcci\u00f3n constitucional (ver, por \u00a0 ejemplo, la Sentencia T-231 de 1994). Este criterio se reiter\u00f3 con posterioridad \u00a0 (Cfr, \u00a0con los fallos T-008 de 1998, T-984 de 1999, T-784 de 2000, SU-159 de 2002 y \u00a0 T-996 de 2003), hasta que se consolid\u00f3 como subregla jurisprudencial en la \u00a0 Sentencia C-590 de 2005. \u00a0 \u00a0<\/p>\n<p>[49] Cfr., Corte Constitucional, Sentencia \u00a0 T-231 de 1994. \u00a0 \u00a0<\/p>\n<p>[50] Cfr., Corte Constitucional, Sentencias \u00a0 SU-089 de 1999 y T-996 de 2003. \u00a0 \u00a0<\/p>\n<p>[51] Cfr., Corte Constitucional, Sentencia \u00a0 T-579 de 2006. \u00a0 \u00a0<\/p>\n<p>[52] Cfr., Corte Constitucional, Sentencias \u00a0 T-996 de 2003 y T-579 de 2006. \u00a0 \u00a0<\/p>\n<p>[53] Cfr., Corte Constitucional, Sentencias \u00a0 SU-159 de 2002, T-331 de 2008, T-719 de 2012 y SU-355 de 2017. \u00a0 \u00a0<\/p>\n<p>[54] Cfr., Corte Constitucional, Sentencia \u00a0 T-674 de 2013. \u00a0 \u00a0<\/p>\n<p>[55] Cfr., Corte Constitucional, Sentencias \u00a0 T-264 de 2009, T-268 de 2010 y T-270 de 2017 \u00a0 \u00a0<\/p>\n<p>[56] Aunque desde sus or\u00edgenes esta Corte desarroll\u00f3 el \u00a0 principio de prevalencia del derecho sustancial frente a lo formal (Ver, por \u00a0 ejemplo, las Sentencias C-004 de 1992 y T-012 de 1992), en materia de tutela \u00a0 contra providencias judiciales, tuvo aplicaci\u00f3n con considerable posterioridad. \u00a0 As\u00ed, en la Sentencia T-1306 de 2001 esta Corporaci\u00f3n comenz\u00f3 precisando que, si \u00a0 bien las normas procesales son constitucionalmente leg\u00edtimas, no pueden \u00a0 convertirse en un obst\u00e1culo para la vigencia del derecho sustancial y la \u00a0 supremac\u00eda de los derechos inalienables del ser humano. Por esta raz\u00f3n, de \u00a0 hallarse que el juez de instancia incurri\u00f3 en un error en la apreciaci\u00f3n de la \u00a0 norma sustancial por una exigencia procedimental desproporcionada, deber\u00eda \u00a0 considerarse que actu\u00f3 con un exceso ritual manifiesto. Este yerro procesal se \u00a0 reiter\u00f3 a lo largo del desarrollo jurisprudencial de la Corte Constitucional, \u00a0 hasta que paulatinamente se incorpor\u00f3 como una modalidad del defecto \u00a0 procedimental (Cfr., \u00a0Corte Constitucional, Sentencias T-1123 de 2002, T-950 de 2003, T-289 de \u00a0 2005, T-1091 de 2008, T-091 de 2008, T-052 de 2009, T-264 de 2009, T-268 de \u00a0 2010, T-429 de 2011, T-893 de 2011, T-213 de 2012, T-926 de 2014 y SU-454 de \u00a0 2016). \u00a0 \u00a0<\/p>\n<p>[57] Cfr., Corte Constitucional, Sentencia \u00a0 T-264 de 2009. \u00a0 \u00a0<\/p>\n<p>[58] Cfr., Corte Constitucional, Sentencias \u00a0 C-131 de 2002, T-268 de 2010, SU-636 de 2015 y SU-215 de 2016. \u00a0 \u00a0<\/p>\n<p>[59] Cfr., Corte Constitucional, Sentencias \u00a0 T-1306 de 2001 y T-579 de 2006. \u00a0 \u00a0<\/p>\n<p>[60] Cfr., Corte Constitucional, Sentencia \u00a0 SU-573 de 2017. \u00a0 \u00a0<\/p>\n<p>[61] Cfr., Corte Constitucional, Sentencia \u00a0 T-453 de 2017. \u00a0 \u00a0<\/p>\n<p>[62] Cfr., Corte Constitucional, Sentencias \u00a0 T-589 de 2003, T-169 de 2005, T-767 de 2006 y T-907 de 2006. \u00a0 \u00a0<\/p>\n<p>[64] Cfr., Corte Constitucional, Sentencias \u00a0 T-121 de 1999, T-114 de 2002, T-1045 de 2008 y SU-399\u00a0 de 2012. \u00a0 \u00a0<\/p>\n<p>[65] Cfr., Corte Constitucional, Sentencia \u00a0 SU-159 de 2002. \u00a0 \u00a0<\/p>\n<p>[66] Cfr., Corte Constitucional, Sentencias \u00a0 T-1036 de 2002 y T-169 de 2005. \u00a0 \u00a0<\/p>\n<p>[67] Cfr., Corte Constitucional, Sentencias \u00a0 T-1222 de 2005 y T-286 de 2007. \u00a0 \u00a0<\/p>\n<p>[68] Cfr., Corte Constitucional, Ib\u00eddem. \u00a0 \u00a0 \u00a0<\/p>\n<p>[69] Cfr., Corte \u00a0 Constitucional, Sentencia T-359 de 2003. \u00a0 \u00a0<\/p>\n<p>[70] Cfr., Corte Constitucional, \u00a0 \u00a0sentencias T-573 de 1997, T-169 de 2005, T-453 de 2005, T-907 de 2006, T-937 de \u00a0 2006, T-1033 de 2007, T-1057 de 2007, T-286 de 2007, SU-817 de 2010, SU-399 de \u00a0 2012, SU-539 de 2012, SU-918 de 2013, SU-950 de 2014, SU-242 de 2015, SU-566 de \u00a0 2015, SU-635 de 2015 y SU-659 de 2015.\u00a0 \u00a0 \u00a0<\/p>\n<p>[71] Cfr., Corte Constitucional, Sentencia \u00a0 T-345 de 1996. \u00a0 \u00a0<\/p>\n<p>[72] Cfr., Corte Constitucional, Sentencias \u00a0 SU-159 de 2002, T-1032 de 2002, T-589 de 2003, T-169 de 2005, T-231 de 2007, \u00a0 T-686 de 2007 y T-769 de 2008. \u00a0 \u00a0<\/p>\n<p>[73] Cfr., Corte Constitucional, Sentencia \u00a0 T-1222 de 2005. \u00a0 \u00a0<\/p>\n<p>[74] Cfr., Corte \u00a0 Constitucional, Sentencia T-169 de 2005. \u00a0 \u00a0<\/p>\n<p>[75] Cfr., Corte \u00a0 Constitucional, Sentencias T-567 de 1998 y T-701 de 2004. \u00a0 \u00a0<\/p>\n<p>[76] Cfr., Corte Constitucional, Sentencia \u00a0 SU-396 de 2017. \u00a0 \u00a0<\/p>\n<p>[77] Cfr., Corte Constitucional, Ib\u00eddem. \u00a0 \u00a0<\/p>\n<p>[78] Cfr., Corte Constitucional, Sentencias \u00a0 T-260 de 1999, T-345 de 1996 y T-1222 de 2005. \u00a0 \u00a0<\/p>\n<p>[79] Cfr., Consejo de Estado, \u00a0 Sala Plena, Sentencia de 23 de julio de 1996; Secci\u00f3n Quinta, Sentencia del 20 \u00a0 de enero de 2006. \u00a0 \u00a0<\/p>\n<p>[80] Cfr., Corte \u00a0 Constitucional, Sentencias T-553 de 2012 y T-398 de 2017. \u00a0 \u00a0<\/p>\n<p>[81] Cfr., \u00a0 Consejo de Estado, Secci\u00f3n Cuarta, Sentencia de 26 de abril de 2002 \/\/ Consejo \u00a0 de Estado, Secci\u00f3n Quinta, Sentencia de 24 de abril de 2003. \u00a0 \u00a0<\/p>\n<p>[82] Cfr., Consejo de Estado, \u00a0 Secci\u00f3n Tercera, Sentencia del 14 de julio de 2016. \u00a0 \u00a0<\/p>\n<p>[83] En esta providencia la Corte \u00a0 decidi\u00f3 la exequibilidad del numeral 4 del art\u00edculo 137 del C\u00f3digo Contencioso \u00a0 Administrativo, \u201cbajo la condici\u00f3n de que cuando el juez administrativo \u00a0 advierta la violaci\u00f3n de un derecho fundamental constitucional de aplicaci\u00f3n \u00a0 inmediata, deber\u00e1 proceder a su protecci\u00f3n, aun cuando el actor en la demanda no \u00a0 hubiere cumplido con el requisito de se\u00f1alar las normas violadas y el concepto \u00a0 de violaci\u00f3n. Igualmente, cuando dicho juez advierte incompatibilidad entre la \u00a0 Constituci\u00f3n y una norma jur\u00eddica tiene la obligaci\u00f3n de aplicar el art. 4 de la \u00a0 Constituci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>[84] En esta oportunidad, el tribunal \u00a0 declar\u00f3 la exequibilidad del art\u00edculo 135 de la Ley 1437 de 2011, que establece \u00a0 la facultad del Consejo de Estado para proferir las decisiones, en el marco de \u00a0 los procesos de nulidad por inconstitucionalidad, con fundamento en la violaci\u00f3n \u00a0 de cualquier norma constitucional. Lo anterior, en la medida que dicha \u00a0 disposici\u00f3n normativa reafirma los principios de supremac\u00eda e integridad del \u00a0 Texto Superior, consagrados en los art\u00edculos 4 y 241 de la Constituci\u00f3n \u00a0 Pol\u00edtica. \u00a0 \u00a0<\/p>\n<p>[85] A trav\u00e9s de esta sentencia, el \u00a0 Tribunal ampar\u00f3 los derechos fundamentales de la parte actora, al considerar que \u00a0 la decisi\u00f3n del Tribunal Contencioso Administrativo de Bol\u00edvar, de revocar la \u00a0 sentencia de primera instancia aduciendo una afectaci\u00f3n al principio de justicia \u00a0 rogada, porque no se aleg\u00f3 la falta de motivaci\u00f3n del acto administrativo de \u00a0 insubsistencia, produjo un defecto sustantivo por la omisi\u00f3n en la aplicaci\u00f3n de \u00a0 normas constitucionales y legales relevantes, as\u00ed como del precedente judicial \u00a0 que resuelve integralmente el caso.\u00a0 \u00a0 \u00a0<\/p>\n<p>[86] Cfr., Consejo de Estado, \u00a0 Secci\u00f3n Quinta. Sentencia del 20 de enero de 2006. \u00a0 \u00a0<\/p>\n<p>[87] Cfr., Consejo de Estado, \u00a0 Secci\u00f3n Tercera. Sentencias del 9 de febrero de 2012 y 11 de Septiembre de 2013. \u00a0 \u00a0<\/p>\n<p>[88] En esa oportunidad, esta \u00a0 Corporaci\u00f3n declar\u00f3 exequible la expresi\u00f3n \u201clas entidades responder\u00e1n por las \u00a0 actuaciones, abstenciones, hechos y omisiones antijur\u00eddicos que les sean \u00a0 imputables y que causen perjuicio a sus contratistas\u201d, contenida en el \u00a0 art\u00edculo 50 de la Ley 80 de 1993, pero condicionando a que su interpretaci\u00f3n \u00a0 deber\u00e1 efectuarse en consonancia con el art\u00edculo 90 de la Constituci\u00f3n, el cual \u00a0 establece una marco general de la responsabilidad del Estado. \u00a0 \u00a0<\/p>\n<p>[89] En esta sentencia la Corte \u00a0 declar\u00f3 exequible el art\u00edculo 86 del antiguo C\u00f3digo Contencioso Administrativo, \u00a0 que establec\u00eda el contenido de la acci\u00f3n de reparaci\u00f3n directa, explicando que \u00a0 el da\u00f1o antijur\u00eddico, como soporte del deber de reparaci\u00f3n estatal, es una \u00a0 acepci\u00f3n que se armoniza \u201ccon los principios y \u00a0 valores propios del Estado Social de Derecho debido a que al Estado corresponde \u00a0 la salvaguarda de los derechos y libertades de los administrados frente a la \u00a0 propia Administraci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>[90] En dicho momento, la Corte \u00a0 Constitucional declar\u00f3 la exequibilidad parcial del art\u00edculo 140 de la Ley 1437 \u00a0 de 2001, el cual contiene los fundamentos normativos de la acci\u00f3n de reparaci\u00f3n \u00a0 directa, expresando que el articulado se encuentra ajustado a la Constituci\u00f3n, \u00a0 en tanto la acci\u00f3n de reparaci\u00f3n directa busca que \u201cla v\u00edctima de un da\u00f1o \u00a0 antijur\u00eddico se encuentra habilitada para demandar del Estado su reparaci\u00f3n, \u00a0 cuando se configure la responsabilidad del mismo, es decir, al establecerse la \u00a0 conducta da\u00f1ina de una agente del Estado, el da\u00f1o y la relaci\u00f3n causal entre \u00a0 \u00e9ste y aqu\u00e9l\u201d. \u00a0 \u00a0<\/p>\n<p>[91] En esta providencia, la \u00a0 Corporaci\u00f3n ampar\u00f3 los derechos fundamentales del actor, al considerar que el \u00a0 Tribunal Administrativo del Meta, en el curso de la acci\u00f3n de reparaci\u00f3n \u00a0 directa, incurri\u00f3 en los defectos f\u00e1ctico y procedimental al dejar de declarar \u00a0 la responsabilidad del Estado porque no se aport\u00f3 el registro civil de \u00a0 nacimiento en la oportunidad procesal prevista. As\u00ed, siguiendo las \u00a0 consideraciones de la Sentencia C-644 de 2011, la Corte se\u00f1al\u00f3 que la reparaci\u00f3n \u00a0 directa \u201ces una acci\u00f3n de naturaleza subjetiva, individual, temporal y \u00a0 desistible, a trav\u00e9s de la cual la persona que se crea lesionada o afectada (\u2026) \u00a0 podr\u00e1\u00a0 solicitar directamente ante la jurisdicci\u00f3n de lo contencioso \u00a0 administrativo que se repare el da\u00f1o causado y se le reconozcan las dem\u00e1s \u00a0 indemnizaciones que correspondan, esto es, sin reclamaci\u00f3n previa a la \u00a0 administraci\u00f3n o mediando petici\u00f3n de nulidad, como en el caso de la acci\u00f3n de \u00a0 restablecimiento del derecho. Se trata de una t\u00edpica acci\u00f3n tendiente a \u00a0 indemnizar a las personas con ocasi\u00f3n de la responsabilidad extracontractual en \u00a0 que pudo incurrir el Estado, en raz\u00f3n de las actividades anteriormente \u00a0 indicadas, que excluyen de entrada el acto administrativo\u201d. \u00a0 \u00a0<\/p>\n<p>[92] Cfr., Corte Constitucional, Sentencias \u00a0 C-644 de 2011 y T-339 de 2015. \u00a0 \u00a0<\/p>\n<p>[93] Cfr. Consejo de Estado, Secci\u00f3n Tercera, \u00a0 Sentencias del 31 de mayo y 5 de diciembre de 2016. \u00a0 \u00a0<\/p>\n<p>[94] Cuaderno principal expediente de \u00a0 tutela, folio 50. \u00a0 \u00a0<\/p>\n<p>[95] Ib\u00eddem. \u00a0 \u00a0<\/p>\n<p>[96] M.P. Cristina Pardo Schlesinger. \u00a0 \u00a0<\/p>\n<p>[97] Fundamento jur\u00eddico N\u00ba 6.1.1. \u00a0 \u00a0<\/p>\n<p>[98] Cfr. Auto 153 de 2018, M.P. Cristina \u00a0 Pardo Schlesinger.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0SU061-18 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 Sentencia SU061\/18 \u00a0 \u00a0 ACCION DE TUTELA CONTRA PROVIDENCIAS \u00a0 JUDICIALES-Requisitos generales y especiales de \u00a0 procedibilidad \u00a0 \u00a0 ACCION DE TUTELA CONTRA PROVIDENCIAS \u00a0 JUDICIALES-Irregularidad procesal debe tener efecto \u00a0 decisivo o determinante en la sentencia que se impugna \u00a0 \u00a0 DEFECTO PROCEDIMENTAL [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-25904","post","type-post","status-publish","format-standard","hentry","category-sentencias-de-unificacion-2018"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/25904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=25904"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/25904\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=25904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=25904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=25904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}