{"id":2646,"date":"2024-05-30T17:01:01","date_gmt":"2024-05-30T17:01:01","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/05\/30\/t-519-96\/"},"modified":"2024-05-30T17:01:01","modified_gmt":"2024-05-30T17:01:01","slug":"t-519-96","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-519-96\/","title":{"rendered":"T 519 96"},"content":{"rendered":"<p>T-519-96<\/p>\n<p>&nbsp; &nbsp; Sentencia T-519\/96 &nbsp;<\/p>\n<p>ACCION DE TUTELA-Hecho superado &nbsp;<\/p>\n<p>Referencia: Expediente T-101.134 &nbsp;<\/p>\n<p>Peticionario: Felipe Royet Gonz\u00e1lez &nbsp;<\/p>\n<p>Tema: &nbsp;<\/p>\n<p>Derecho de petici\u00f3n &nbsp;<\/p>\n<p>Hecho Superado. &nbsp;<\/p>\n<p>Magistrado Ponente: &nbsp;<\/p>\n<p>Dr. ANTONIO BARRERA CARBONELL &nbsp;<\/p>\n<p>Santaf\u00e9 de Bogot\u00e1, D.C., Octubre nueve (9) de mil novecientos noventa y seis (1996). &nbsp;<\/p>\n<p>ANTECEDENTES. &nbsp;<\/p>\n<p>1. La pretensi\u00f3n y los hechos. &nbsp;<\/p>\n<p>El doctor Felipe Royet Gonz\u00e1lez, interpone la presente acci\u00f3n de tutela en contra del Gerente de la Empresa Municipal de Tel\u00e9fonos de Barranquilla, ya que desde el 6 de febrero de 1996, elev\u00f3 una petici\u00f3n respetuosa para que le informe la raz\u00f3n del cobro de \u201cderechos de conexi\u00f3n\u201d de su l\u00ednea telef\u00f3nica que fueron cancelados, sin embargo, afirma el peticionario, a la fecha de interposici\u00f3n de la acci\u00f3n de tutela, a\u00fan no existe respuesta al respecto. &nbsp; &nbsp;<\/p>\n<p>Con la presente acci\u00f3n, el actor pretende se ordene a la entidad demandada resolver la petici\u00f3n formulada e instalar el servicio telef\u00f3nico suspendido, situaci\u00f3n que le ha generado perjuicios econ\u00f3micos y morales de enorme envergadura. &nbsp;Dentro del tr\u00e1mite de instancia, la entidad demandada interviene manifestando que las peticiones formuladas fueron oportunamente resueltas, sin embargo, el servicio no se ha instalado nuevamente, por falta de pago del valor correspondiente al consumo del servicio. &nbsp; &nbsp;<\/p>\n<p>el Juzgado 13 Penal del Circuito de Barranquilla, en sentencia de mayo 28 de 1996, decidi\u00f3 negar la acci\u00f3n de tutela, al considerar que para la reclamaci\u00f3n de da\u00f1os y perjuicios, existe otros medios de defensa judicial, como la jurisdicci\u00f3n contencioso administrativa,&nbsp; &nbsp;<\/p>\n<p>III. FUNDAMENTOS JUR\u00cdDICOS. &nbsp;<\/p>\n<p>3.1. Competencia. &nbsp;<\/p>\n<p>La Sala es competente para hacer la revisi\u00f3n de la aludida sentencia, seg\u00fan los art\u00edculos 86 inciso 2\u00ba y 241 numeral 9\u00ba de la Constituci\u00f3n, en concordancia con los art\u00edculos 33, 34, 35 y 36 del Decreto 2591 de 1991. &nbsp;<\/p>\n<p>3.2. Sentencias que se reiteran &nbsp;<\/p>\n<p>Resulta claro que la causa que gener\u00f3 la transgresi\u00f3n del derecho de petici\u00f3n ya se super\u00f3, toda vez que la entidad demandada, resolvi\u00f3 la solicitud que origin\u00f3 la presente acci\u00f3n y descont\u00f3 el valor equivocadamente cobrado. &nbsp;Por consiguiente, la acci\u00f3n de tutela no est\u00e1 llamada a prosperar, pues perdi\u00f3 su efectividad, en raz\u00f3n de que en la actualidad no existe vulneraci\u00f3n de derecho fundamental alguno, que amerite una orden del juez tendiente a restablecer derechos constitucionales amenazados o vulnerados.&nbsp; &nbsp;<\/p>\n<p>De otra parte, en relaci\u00f3n con la conexi\u00f3n del servicio telef\u00f3nico, la Sala estima que esa pretensi\u00f3n se entiende atendida una vez se efectu\u00f3 el pago en menci\u00f3n, de acuerdo con lo expresado por la entidad demandada. &nbsp;En cuanto y al pago del valor de perjuicios ocasionados, esta Sala de Revisi\u00f3n considera que no es procedente, pues acceder a ello desborda la competencia del juez de tutela. &nbsp;<\/p>\n<p>IV. DECISI\u00d3N &nbsp;<\/p>\n<p>Por lo expuesto, la Sala Segunda de Revisi\u00f3n de la Corte Constitucional, administrando justicia en nombre del pueblo y por autoridad de la Constituci\u00f3n,&nbsp; &nbsp;<\/p>\n<p>Primero. CONFIRMAR la sentencia proferida dentro del expediente T-101.134, por el Juzgado 13 Penal del Circuito de Barranquilla. &nbsp;<\/p>\n<p>Segundo. COMUNICAR a trav\u00e9s de la Secretar\u00eda General de la Corte Constitucional, el contenido de la sentencia al Juzgado 13 Penal del Circuito de Barranquilla. &nbsp;<\/p>\n<p>C\u00f3piese, notif\u00edquese, comun\u00edquese, c\u00famplase e ins\u00e9rtese en la Gaceta de la Corte Constitucional. &nbsp;<\/p>\n<p>ANTONIO BARRERA CARBONELL &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>EDUARDO CIFUENTES MU\u00d1OZ &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>CARLOS GAVIRIA D\u00cdAZ &nbsp;<\/p>\n<p>MARTHA SACHICA DE MONCALEANO &nbsp;<\/p>\n<p>Secretaria General &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>T-519-96 &nbsp; &nbsp; Sentencia T-519\/96 &nbsp; ACCION DE TUTELA-Hecho superado &nbsp; Referencia: Expediente T-101.134 &nbsp; Peticionario: Felipe Royet Gonz\u00e1lez &nbsp; Tema: &nbsp; Derecho de petici\u00f3n &nbsp; Hecho Superado. &nbsp; Magistrado Ponente: &nbsp; Dr. ANTONIO BARRERA CARBONELL &nbsp; Santaf\u00e9 de Bogot\u00e1, D.C., Octubre nueve (9) de mil novecientos noventa y seis (1996). &nbsp; ANTECEDENTES. &nbsp; 1. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-2646","post","type-post","status-publish","format-standard","hentry","category-tutelas-1996"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/2646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=2646"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/2646\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=2646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=2646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=2646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}