{"id":26624,"date":"2024-07-02T17:18:00","date_gmt":"2024-07-02T17:18:00","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/07\/02\/t-024-19\/"},"modified":"2024-07-02T17:18:00","modified_gmt":"2024-07-02T17:18:00","slug":"t-024-19","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-024-19\/","title":{"rendered":"T-024-19"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-024-19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia T-024\/19 \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA PARA RECONOCIMIENTO DE PENSION DE INVALIDEZ-Procedencia excepcional \u00a0 \u00a0<\/p>\n<p>LEGITIMACION POR ACTIVA EN TUTELA-Formas previstas por \u00a0 ordenamiento jur\u00eddico \u00a0 \u00a0<\/p>\n<p>ACTO DE APODERAMIENTO-Concepto\/APODERADO JUDICIAL EN \u00a0 TUTELA-Requisitos \u00a0 \u00a0<\/p>\n<p>Esta Corporaci\u00f3n ha precisado que i) \u00a0 es un acto jur\u00eddico formal, por lo cual debe realizarse por escrito; ii) se \u00a0 concreta en un escrito, llamado poder que se presume autentico; iii) debe ser un \u00a0 poder especial; iv) el poder conferido para la promoci\u00f3n o para la defensa de \u00a0 los intereses en un determinado proceso no se entiende conferido para instaurar \u00a0 procesos diferentes, as\u00ed los hechos que le den fundamento a estos tengan origen \u00a0 en el proceso inicial; v) el destinatario del acto de apoderamiento solo puede \u00a0 ser un profesional del derecho habilitado con tarjeta profesional \u00a0 \u00a0<\/p>\n<p>LEGITIMACION POR ACTIVA EN TUTELA-Improcedencia de tutela por cuanto \u00a0 apoderado judicial no cuenta con poder especial \u00a0 \u00a0<\/p>\n<p>PRINCIPIOS DE SUMARIEDAD, CELERIDAD E INFORMALIDAD DE LA ACCION DE TUTELA-Procedencia excepcional de tutela en caso de apoderado judicial, \u00a0 quien ten\u00eda suspensi\u00f3n de tarjeta profesional de abogado, representando a sujeto \u00a0 de especial protecci\u00f3n constitucional \u00a0 \u00a0<\/p>\n<p>APLICACION DEL PRINCIPIO DE LA CONDICION MAS BENEFICIOSA A LA PENSION DE \u00a0 INVALIDEZ-Alcance \u00a0 \u00a0<\/p>\n<p>La \u00a0 Corte Constitucional, en sentencia SU-442 de 2016, indico que la solicitud de \u00a0 amparo es procedente si se emplea cuando i) el actor no dispone de otro medio \u00a0 judicial de defensa; o ii) existen otros medios de defensa judicial pero es \u00a0 necesaria la tutela para evitar la consumaci\u00f3n de un perjuicio irremediable; o \u00a0 iii) los recursos disponibles no son id\u00f3neos o eficaces, toda vez que su sola \u00a0 existencia formal no es garant\u00eda de su utilidad en el caso concreto. En esa \u00a0 medida, destaco que es competencia del juez constitucional examinar cual es la \u00a0 eficacia que, en concreto, tiene el otro instrumento de protecci\u00f3n, para lo \u00a0 cual, se debe verificar si \u201clos otros medios de defensa proveen un remedio \u00a0 integral y si son expeditos para evitar un perjuicio irremediable \u00a0 \u00a0<\/p>\n<p>SUJETOS DE ESPECIAL PROTECCION CONSTITUCIONAL QUE SE \u00a0 ENCUENTRAN EN UN ESTADO DE DEBILIDAD MANIFIESTA-Flexibilidad \u00a0 del juez constitucional al estudiar procedencia de la acci\u00f3n de tutela para \u00a0 reconocimiento de pensi\u00f3n de invalidez \u00a0 \u00a0<\/p>\n<p>PRINCIPIO DE LA CONDICION MAS BENEFICIOSA A LA PENSION DE INVALIDEZ-No se restringe \u00a0 exclusivamente a admitir u ordenar la aplicaci\u00f3n de la norma inmediatamente \u00a0 anterior a la vigente, sino que se extiende a todo esquema normativo anterior \u00a0 bajo cuyo amparo el afiliado o beneficiario haya contra\u00eddo una expectativa \u00a0 leg\u00edtima \u00a0 \u00a0<\/p>\n<p>PRINCIPIO DE LA CONDICION MAS BENEFICIOSA A LA PENSION DE INVALIDEZ-Reiteraci\u00f3n de sentencia SU442\/16 \u00a0 \u00a0<\/p>\n<p>PRINCIPIO DE LA CONDICION MAS BENEFICIOSA A LA PENSION DE INVALIDEZ-Orden a \u00a0 Colpensiones reconocer y pagar pensi\u00f3n de invalidez por cumplir requisitos \u00a0 \u00a0<\/p>\n<p>Referencia: Expediente T-6.964.270 \u00a0 \u00a0<\/p>\n<p>Acci\u00f3n de tutela formulada por el se\u00f1or Lizardo Narv\u00e1ez Valencia \u00a0 contra Colpensiones \u00a0 \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0 \u00a0<\/p>\n<p>CARLOS BERNAL PULIDO \u00a0 \u00a0<\/p>\n<p>Bogot\u00e1, D.C., veintiocho (28) de enero de dos mil diecinueve (2019) \u00a0 \u00a0<\/p>\n<p>La Sala Primera de Revisi\u00f3n de la Corte Constitucional, \u00a0 integrada por la magistrada Diana Fajardo Rivera y los magistrados Luis \u00a0 Guillermo Guerrero P\u00e9rez y Carlos Bernal Pulido, quien la preside, en ejercicio \u00a0 de sus competencias constitucionales y legales, ha proferido la siguiente \u00a0 \u00a0<\/p>\n<p>SENTENCIA \u00a0 \u00a0<\/p>\n<p>En el tr\u00e1mite de revisi\u00f3n del fallo adoptado en \u00fanica \u00a0 instancia por el Juzgado Primero Civil del Circuito Especializado en Restituci\u00f3n \u00a0 de Tierras de Pereira, el 20 de junio de 2018. \u00a0 \u00a0<\/p>\n<p>Conforme a lo dispuesto en los art\u00edculos 86 de la \u00a0 Constituci\u00f3n Pol\u00edtica y 33 del Decreto-ley 2591 de 1991, la Sala de Selecci\u00f3n \u00a0 n\u00famero 9 de la Corte Constitucional escogi\u00f3 para efectos de revisi\u00f3n el asunto \u00a0 de la referencia. \u00a0 \u00a0<\/p>\n<p>I. ANTECEDENTES[1] \u00a0 \u00a0<\/p>\n<p>1. El 6 \u00a0 de junio de 2018, la apoderada judicial Gloria Yobana Castro Torres, actuando en \u00a0 representaci\u00f3n del se\u00f1or Lizardo Narv\u00e1ez Valencia, formul\u00f3 acci\u00f3n de tutela en \u00a0 contra de la Administradora Colombiana de Pensiones\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u2013 en adelante Colpensiones\u2013, con el prop\u00f3sito de que se protegieran los \u00a0 derechos fundamentales a la seguridad social, vida digna y m\u00ednimo vital, de su \u00a0 representado. \u00a0 \u00a0<\/p>\n<p>1. \u00a0 Hechos probados \u00a0 \u00a0<\/p>\n<p>2. El 7 \u00a0 de diciembre de 2002, el se\u00f1or Lizardo Narv\u00e1ez Valencia, quien tiene 65 a\u00f1os de \u00a0 edad, fue v\u00edctima de un atentado por parte de un grupo armado al margen de la \u00a0 ley. Como consecuencia de aquel, recibi\u00f3 varios disparos de arma de fuego en su \u00a0 rostro y pierna derecha que le generaron secuelas e incapacidades definitivas. \u00a0 \u00a0<\/p>\n<p>3. El \u00a0 25 de julio de 2016, la Junta Regional de Calificaci\u00f3n de Invalidez de Risaralda \u00a0 le dictamin\u00f3 al se\u00f1or Narv\u00e1ez Valencia una p\u00e9rdida de capacidad laboral del \u00a0 52.54%, con fecha de estructuraci\u00f3n del 15 de febrero de 2016[2]. \u00a0 \u00a0<\/p>\n<p>4. Con \u00a0 ocasi\u00f3n de dicha invalidez, el 23 de noviembre de 2016, el se\u00f1or Narv\u00e1ez \u00a0 Valencia solicit\u00f3 a Colpensiones el reconocimiento de su pensi\u00f3n de invalidez[3]. \u00a0 Sin embargo, mediante la Resoluci\u00f3n GNR 376868 de 9 de diciembre de 2016, la \u00a0 mencionada instituci\u00f3n neg\u00f3 esta solicitud, habida cuenta de que \u201cno \u00a0 satisfizo los requisitos establecidos en el art\u00edculo 1 de la Ley 860 de 2003, \u00a0 esto es, tener 50 semanas dentro de los \u00faltimos tres (3) a\u00f1os inmediatamente \u00a0 anteriores a la fecha de estructuraci\u00f3n de invalidez\u201d[4]. \u00a0 \u00a0<\/p>\n<p>5. El 23 de marzo de \u00a0 2017, el se\u00f1or Narv\u00e1ez Valencia requiri\u00f3 nuevamente a Colpensiones el \u00a0 reconocimiento y pago de su pensi\u00f3n de invalidez. Sin embargo, mediante \u00a0 la Resoluci\u00f3n SUB 65297 de mayo 15 de 2017, la instituci\u00f3n aludida le neg\u00f3 dicha \u00a0 petici\u00f3n, como quiera que no cumpli\u00f3 con el requisito de estar cotizando al \u00a0 momento de la estructuraci\u00f3n de la invalidez, por cuanto solo cotiz\u00f3 hasta el 15 \u00a0 de abril de 1989. Tampoco encontr\u00f3 acreditado el requisito correspondiente a la \u00a0 cotizaci\u00f3n de 26 semanas dentro del a\u00f1o anterior a la fecha de estructuraci\u00f3n de \u00a0 la invalidez[5]. \u00a0 \u00a0<\/p>\n<p>6. El \u00a0 14 de diciembre de 2017, el tutelante ingres\u00f3 a la Cl\u00ednica Los Rosales de \u00a0 Pereira con un fuerte dolor de cabeza y, adem\u00e1s, presentaba s\u00edntomas de visi\u00f3n \u00a0 borrosa y fosfenos, hemianopsia hom\u00f3nima, desorientaci\u00f3n ocasional, lenguaje \u00a0 incoherente, fallo en la memoria y n\u00e1useas. En esa misma fecha, luego de una \u00a0 intervenci\u00f3n neuroquir\u00fargica, le fue detectada una lesi\u00f3n tumoral en el cerebro[6]. \u00a0 \u00a0<\/p>\n<p>2. Pretensiones y fundamentos \u00a0 \u00a0<\/p>\n<p>7. El accionante pidi\u00f3 el amparo de los derechos fundamentales a la \u00a0 seguridad social, vida digna y m\u00ednimo vital y, por consiguiente, que se ordene a \u00a0 Colpensiones que, de manera transitoria, \u201cle reconozca y pague su pensi\u00f3n de \u00a0 invalidez al haber acreditado los requisitos establecidos en el Acuerdo 049 de \u00a0 1990, en virtud del principio constitucional de la condici\u00f3n m\u00e1s beneficiosa\u201d[7]. \u00a0 \u00a0<\/p>\n<p>3. Respuesta de la entidad \u00a0 accionada \u00a0 \u00a0<\/p>\n<p>9. En el auto admisorio de la acci\u00f3n de \u00a0 tutela, del 7 de junio del a\u00f1o en curso, se orden\u00f3 notificar de la solicitud de \u00a0 amparo a Colpensiones[9]. \u00a0 \u00a0<\/p>\n<p>10. Colpensiones, por intermedio del Director de Acciones Constitucionales de la \u00a0 Gerencia de Defensa Judicial, se opuso a la prosperidad de las pretensiones. La \u00a0 referida entidad solicit\u00f3 que se declarara \u201cla improcedencia de la presente \u00a0 acci\u00f3n, por cuanto no concurren, o no fueron acreditados los criterios que \u00a0 habilitan la acci\u00f3n de tutela como mecanismo transitorio, y se declare la \u00a0 improcedencia, por cuanto no hay una obligaci\u00f3n legalmente constituida frente a \u00a0 Colpensiones\u201d[10]. \u00a0 \u00a0<\/p>\n<p>4. Decisi\u00f3n objeto de revisi\u00f3n \u00a0 \u00a0<\/p>\n<p>11. El 20 de junio de 2018, el Juzgado \u00a0 Primero Civil del Circuito Especializado en Restituci\u00f3n de Tierras de Pereira \u00a0 neg\u00f3 el amparo de tutela solicitado, debido a que en el presente asunto no \u00a0 resultaba procedente la aplicaci\u00f3n del Acuerdo 049 de 1990, de conformidad con \u00a0 la postura adoptada por la Sala de Casaci\u00f3n Laboral de la Corte Suprema de \u00a0 Justicia[11]. \u00a0 \u00a0\u00a0<\/p>\n<p>12. La anterior decisi\u00f3n fue \u00a0 impugnada por la apoderada judicial del tutelante. No obstante, mediante auto de \u00a0 4 de julio de 2018, la referida autoridad judicial se neg\u00f3 a conceder el recurso \u00a0 de apelaci\u00f3n por falta de legitimaci\u00f3n en la causa por activa, comoquiera que la \u00a0 profesional del derecho ten\u00eda \u201cuna suspensi\u00f3n de su tarjeta profesional de 3 \u00a0 meses, desde el 31 de mayo de 2018 hasta el 30 de agosto de 2018\u201d. Esta \u00a0 situaci\u00f3n fue expuesta por el juez en los siguientes t\u00e9rminos: \u00a0 \u00a0<\/p>\n<p>\u201cEs claro que quien act\u00faa \u00a0 dentro del marco legal y bajo las reglas propias de la profesi\u00f3n de abogado debe \u00a0 acreditar que lo es, seg\u00fan el Decreto 196 de 1971. Ello no solamente por raz\u00f3n \u00a0 de la responsabilidad que implica tal ejercicio, que se concreta en el campo \u00a0 disciplinario, sino por la necesaria defensa de los intereses del cliente, a \u00a0 quien conviene establecer con certidumbre que quien lo apodera puede actuar, de \u00a0 acuerdo con la ley, ante las distintas instancias judiciales y que responder\u00e1 \u00a0 por su gesti\u00f3n. \u00a0 \u00a0\u00a0<\/p>\n<p>Al respecto debe recordarse \u00a0 que, seg\u00fan el art\u00edculo 26 de la Constituci\u00f3n, si bien toda persona es libre de \u00a0 escoger profesi\u00f3n u oficio, la ley podr\u00e1 exigir t\u00edtulos de idoneidad y las \u00a0 autoridades competentes inspeccionar\u00e1n y vigilar\u00e1n el ejercicio de las \u00a0 profesiones. \u00a0 \u00a0<\/p>\n<p>Adem\u00e1s, para ejercer la \u00a0 representaci\u00f3n con base en mandato judicial y actuando el apoderado a t\u00edtulo \u00a0 profesional, as\u00ed sea en materia de tutela, es indispensable que aquel sea \u00a0 abogado titulado y en ejercicio, de conformidad con las normas del Decreto 196 \u00a0 de 1971. Siendo el principal efecto del apoderamiento, es el de perfeccionar la \u00a0 legitimaci\u00f3n en la causa por activa, por lo cual el juez de tutela estar\u00e1 en la \u00a0 obligaci\u00f3n, despu\u00e9s de constatar sus elementos, de proceder a pronunciarse de \u00a0 fondo sobre los hechos y las pretensiones relacionados en el escrito de acci\u00f3n \u00a0 respectivo. (\u2026). \u00a0 \u00a0<\/p>\n<p>Dicho lo anterior y atendiendo \u00a0 el informe secretarial que antecede, donde se observa\u00a0 que la recurrente \u00a0 tiene una suspensi\u00f3n de su tarjeta profesional de 3 meses, desde el 31 de mayo \u00a0 de 2018 hasta el 30 de agosto de 2018, no se concede la impugnaci\u00f3n interpuesta \u00a0 por falta de legitimaci\u00f3n en la causa por activa, contra la sentencia fechada \u00a0 veinte (20) de junio de dos mil dieciocho (2018), proferida dentro de la acci\u00f3n \u00a0 de tutela de la referencia. \u00a0 \u00a0<\/p>\n<p>Adem\u00e1s se ordenar\u00e1 compulsar copias a la Sala Jurisdiccional Disciplinaria del \u00a0 Consejo Seccional de la Judicatura de Risaralda para que investigue la falta en \u00a0 la que pudo incurrir la abogada Gloria Yobana Castro Torres al adelantar la \u00a0 presente acci\u00f3n de tutela teniendo su tarjeta profesional no vigente\u201d[12]. \u00a0 \u00a0<\/p>\n<p>II. CONSIDERACIONES \u00a0 \u00a0<\/p>\n<p>1. \u00a0 Competencia \u00a0 \u00a0<\/p>\n<p>13.\u00a0 Esta Sala de Revisi\u00f3n de la Corte Constitucional es competente para \u00a0 revisar el fallo de tutela proferido dentro del tr\u00e1mite de la referencia, con \u00a0 fundamento en lo dispuesto por el inciso 3\u00b0 del art\u00edculo 86 y el numeral 9 del \u00a0 art\u00edculo 241 de la Constituci\u00f3n Pol\u00edtica, en concordancia con los art\u00edculos 33, \u00a0 34, 35 y 36 del Decreto-ley 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>2. \u00a0 An\u00e1lisis del problema jur\u00eddico de procedibilidad \u00a0 \u00a0<\/p>\n<p>14.\u00a0 Le corresponde a esta Sala de Revisi\u00f3n determinar si la acci\u00f3n de \u00a0 tutela es procedente, por satisfacer los requisitos de procedencia de la acci\u00f3n \u00a0 de tutela. En caso de que lo sea, luego, le corresponde a la Sala formular y \u00a0 resolver los problemas jur\u00eddicos sustanciales del caso en concreto. \u00a0 \u00a0<\/p>\n<p>15. La acci\u00f3n de tutela fue concebida como un mecanismo de protecci\u00f3n inmediato, \u00a0 oportuno y adecuado para las garant\u00edas fundamentales, frente a situaciones de \u00a0 amenaza o vulneraci\u00f3n, ya fuera por la acci\u00f3n u omisi\u00f3n de las autoridades \u00a0 p\u00fablicas, o de los particulares en casos excepcionales. De lo dispuesto por el \u00a0 art\u00edculo 86 de la Constituci\u00f3n y el Decreto-ley 2591 de 1991 se ha considerado, \u00a0 pac\u00edficamente, por esta Corte, que son requisitos para la procedencia o estudio \u00a0 de fondo de la acci\u00f3n de tutela la acreditaci\u00f3n de legitimaci\u00f3n en la causa, un \u00a0 ejercicio subsidiario y un ejercicio oportuno (inmediatez). \u00a0 \u00a0<\/p>\n<p>2.1. Cuesti\u00f3n previa: Acci\u00f3n de tutela formulada mediante apoderado judicial \u00a0 \u00a0<\/p>\n<p>16. La jurisprudencia constitucional ha se\u00f1alado que una de las caracter\u00edsticas \u00a0 esenciales de la acci\u00f3n de tutela es la informalidad para su ejercicio, \u00a0 comoquiera que, precisamente, se trata de un medio judicial instituido para la \u00a0 defensa de los derechos fundamentales, que seg\u00fan el querer del Constituyente, ha \u00a0 sido puesto al alcance de todas las personas para ejercerlo directamente o por \u00a0 conducto de otros[13]. \u00a0 \u00a0<\/p>\n<p>17. En efecto, la Corte ha precisado que la Constituci\u00f3n instituy\u00f3 la acci\u00f3n de \u00a0 tutela para todas las personas y, en consecuencia, \u201cno limita las \u00a0 posibilidades de acudir a ella por razones de nacionalidad, sexo, edad, origen \u00a0 de raza o capacidades intelectuales, raz\u00f3n por la cual es factible que la \u00a0 ejerzan los ni\u00f1os, los ind\u00edgenas, los presos, los campesinos, los analfabetas y \u00a0 en general todo individuo de la especie humana que se halle dentro del \u00a0 territorio colombiano\u201d[14]. \u00a0 Por lo tanto, cualquier exigencia \u201cque pretenda limitar o dificultar su uso, \u00a0 su tr\u00e1mite o su decisi\u00f3n por fuera de las muy simples condiciones determinadas \u00a0 en las normas pertinentes\u201d[15]. \u00a0 \u00a0<\/p>\n<p>18. Ciertamente, el art\u00edculo 86 de la Constituci\u00f3n dispuso que cualquier \u00a0 persona, por s\u00ed misma o por intermedio de otra que act\u00fae a su nombre, puede \u00a0 promover dicha acci\u00f3n constitucional. Por su parte, el art\u00edculo 10 del \u00a0 Decreto-ley 2591 de 1991 consagr\u00f3 las reglas que reglamentan la legitimaci\u00f3n en \u00a0 la causa por activa para el ejercicio de la acci\u00f3n de tutela, as\u00ed: \u00a0 \u00a0<\/p>\n<p>a. Puede ser \u00a0 ejercida, en todo momento y lugar, por cualquier persona vulnerada o amenazada \u00a0 en uno de sus derechos fundamentales. \u00a0 \u00a0<\/p>\n<p>b. Cuando la persona \u00a0 vulnerada o amenazada no ejercita de manera directa la acci\u00f3n, puede hacerlo por \u00a0 intermedio de otra, y para ello tiene varias alternativas: \u00a0 \u00a0<\/p>\n<p>\u00a7\u00a0 \u00a0 \u00a0Mediante la figura de agencia oficiosa, siempre que se manifieste las razones \u00a0 por las cuales los interesados no pueden actuar directamente[16]. \u00a0 \u00a0<\/p>\n<p>\u00a7\u00a0 \u00a0 \u00a0Por medio del Defensor del Pueblo y los personeros municipales[17]. \u00a0 \u00a0<\/p>\n<p>\u00a7\u00a0 \u00a0 \u00a0Por conducto de un representante judicial debidamente habilitado que debe \u00a0 cumplir con las condiciones b\u00e1sicas y fundamentales para el ejercicio de la \u00a0 profesi\u00f3n de abogado[18]. \u00a0 \u00a0<\/p>\n<p>19. Respecto de la \u00faltima hip\u00f3tesis, en lo que tiene que ver con el ejercicio de \u00a0 la profesi\u00f3n de abogado, el art\u00edculo 24 del Decreto 196 de 1971[19] dispuso que \u201cno se podr\u00e1 ejercer la profesi\u00f3n de abogado ni anunciarse \u00a0 como tal sin estar inscrito y tener vigente la inscripci\u00f3n\u201d. De igual forma, el art\u00edculo 25 se\u00f1al\u00f3 que \u201cnadie podr\u00e1 \u00a0 litigar en causa propia o ajena si no es abogado\u201d. \u00a0 \u00a0<\/p>\n<p>20. De igual manera, constituye una causal de incompatibilidad para el ejercicio \u00a0 de la abogac\u00eda, que el profesional del derecho se encuentre suspendido o \u00a0 excluido de la profesi\u00f3n, aunque se halle inscrito, tal como lo dispone el \u00a0 art\u00edculo 29 del C\u00f3digo Disciplinario del Abogado[20]. \u00a0 \u00a0<\/p>\n<p>21. Ahora bien, en lo que tiene que \u00a0 ver con el apoderamiento judicial en materia de tutela, esta \u00a0 Corporaci\u00f3n ha precisado que i) es un acto jur\u00eddico formal, por lo \u00a0 cual debe realizarse por escrito; ii) se concreta en un escrito, \u00a0 llamado poder que se presume aut\u00e9ntico; iii) debe ser un poder \u00a0 especial; iv) el poder conferido para la promoci\u00f3n o para la \u00a0 defensa de los intereses en un determinado proceso no se entiende conferido para \u00a0 instaurar procesos diferentes, as\u00ed los hechos que le den fundamento a estos \u00a0 tengan origen en el proceso inicial; v) el destinatario del \u00a0 acto de apoderamiento s\u00f3lo puede ser un profesional del derecho \u00a0 habilitado con \u00a0 tarjeta profesional.[21] \u00a0 \u00a0<\/p>\n<p>22. De igual forma, la Corte ha enfatizado que cuando la acci\u00f3n de tutela se \u00a0 ejerce mediante representante judicial, es necesario que tenga la calidad de \u00a0 abogado inscrito; as\u00ed lo ha manifestado esta Corporaci\u00f3n en otras decisiones, al \u00a0 advertir que \u201cque cuando una persona act\u00faa por medio de mandatario judicial, \u00a0 las circunstancias procesales cambian, por cuanto en este evento, se hace \u00a0 necesario acompa\u00f1ar\u00a0 a la demanda el poder por medio del cual se act\u00faa, so \u00a0 pena de infracci\u00f3n al r\u00e9gimen de la acci\u00f3n de tutela y al del ejercicio de la \u00a0 profesi\u00f3n de abogado\u201d[22]. \u00a0 \u00a0<\/p>\n<p>23. Dilucidado lo anterior, se tiene que en este asunto el se\u00f1or Lizardo Narv\u00e1ez \u00a0 Valencia le otorg\u00f3 poder especial a los abogados Gloria Yobana Castro Torres y \u00a0 Exynober Ca\u00f1\u00f3n Reyes para que iniciaran y llevaran a cabo acci\u00f3n de tutela \u00a0 contra la Administradora Colombiana de Pensiones \u2013Colpensiones[23]. \u00a0 \u00a0<\/p>\n<p>24. No obstante, se observa que dicho documento fue suscrito por el se\u00f1or \u00a0 Narv\u00e1ez Valencia, no as\u00ed por los apoderados aludidos. Por lo que, se puede \u00a0 concluir que dicho poder no fue aceptado expresamente por los profesionales del \u00a0 derecho. Con todo, lo cierto es que el \u00faltimo inciso del art\u00edculo 74 del C\u00f3digo \u00a0 General del Proceso dispone que los \u201cpoderes podr\u00e1n ser aceptados \u00a0 expresamente o por su ejercicio\u201d, en esa medida, como la acci\u00f3n de \u00a0 tutela fue formulada, \u00fanica y exclusivamente, por la abogada Gloria Yobana \u00a0 Castro Torres, se concluye que solo esta apoderada acept\u00f3 el poder conferido por \u00a0 el se\u00f1or Narv\u00e1ez Valencia para interponer la presente acci\u00f3n de tutela. \u00a0 \u00a0<\/p>\n<p>25. Ahora bien, esta Sala de Revisi\u00f3n encuentra que el juez de tutela de primera \u00a0 instancia se abstuvo de conceder la impugnaci\u00f3n presentada por la doctora Gloria \u00a0 Yobana Castro Torres en contra de la decisi\u00f3n dictada el 20 de junio de 2018, \u00a0 debido a que la recurrente ten\u00eda \u201cuna suspensi\u00f3n de su tarjeta profesional de \u00a0 3 meses, desde el 31 de mayo de 2018 hasta el 30 de agosto de 2018\u201d. En \u00a0 efecto, una vez consultado el certificado de antecedentes disciplinarios de \u00a0 abogados de la referida profesional[24] \u00a0se observ\u00f3 lo siguiente: \u00a0 \u00a0<\/p>\n<p>\u201cQue revisados los \u00a0 archivos de antecedentes de esta Corporaci\u00f3n as\u00ed como los del Tribunal \u00a0 Disciplinario, aparecen registradas las siguientes sanciones, contra la doctora \u00a0 Gloria Yobana Castro Torres identificada con la c\u00e9dula de ciudadan\u00eda xxxxx y la \u00a0 tarjeta de abogada No. xxxxx. \u00a0 \u00a0<\/p>\n<p>(\u2026). \u00a0 \u00a0<\/p>\n<p>Origen: CONSEJO \u00a0 SECCIONAL DE LA JUDICATURA PEREIRA (RISARALDA) SALA JURISDICCIONAL DISCIPLINARIA \u00a0 \u00a0<\/p>\n<p>No. Expediente: \u00a0 66001110200020140039401 \u00a0 \u00a0<\/p>\n<p>Ponente: FIDALGO \u00a0 JAVIER ESTUPI\u00d1\u00c1N CARVAJAL\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>Fecha Sentencia: \u00a0 26-Jul-2017 \u00a0 \u00a0<\/p>\n<p>Sanci\u00f3n: Suspensi\u00f3n \u00a0 D\u00edas: 0\u00a0\u00a0\u00a0 Meses: 3\u00a0 A\u00f1os: 0 \u00a0 \u00a0<\/p>\n<p>Inicio Sanci\u00f3n:\u00a0\u00a0 \u00a0 31-May-2018 Final Sanci\u00f3n: 30-Ago-2018\u201d (Se destaca). \u00a0 \u00a0<\/p>\n<p>26. A partir de la informaci\u00f3n corroborada con este certificado, se tiene que en \u00a0 este caso la acci\u00f3n de tutela fue presentada por la doctora Gloria Yobana Castro \u00a0 Torres ante la Oficina Judicial Seccional Pereira el 6 de junio de 2018, \u00a0 fecha en la cual se encontraba vigente la sanci\u00f3n de suspensi\u00f3n impuesta a la \u00a0 mencionada abogada por la Sala Jurisdiccional Disciplinaria del Consejo \u00a0 Seccional de la Judicatura de Pereira mediante la sentencia de 26 de julio de \u00a0 2017. En esa medida, para esta Sala no hay asomo de duda de que dicha abogada no \u00a0 pod\u00eda aceptar el poder respectivo, por cuanto para el momento de presentaci\u00f3n de \u00a0 la acci\u00f3n de tutela no se encontraba en ejercicio. \u00a0 \u00a0<\/p>\n<p>27. Ahora bien, en aquellos eventos en los cuales la acci\u00f3n de tutela se \u00a0 present\u00f3 por intermedio de apoderado judicial, pero el abogado no contaba con \u00a0 poder especial, la jurisprudencia constitucional se\u00f1al\u00f3, como consecuencia \u00a0 jur\u00eddica, la improcedencia de la solicitud de amparo por falta de legitimaci\u00f3n \u00a0 en la causa por activa. A continuaci\u00f3n se identifican las decisiones en las que \u00a0 se ha optado por dicha consecuencia jur\u00eddica. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Hechos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Ratio decidendi \u00a0\u00a0<\/p>\n<p>T-001 de 1997 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>En este asunto, se analizaron unas acciones de tutela instauradas contra el \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Fondo de\u00a0 Pasivo\u00a0 Social\u00a0 de\u00a0 la\u00a0 Empresa\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Puertos\u00a0 de\u00a0 Colombia -FONCOLPUERTOS-, mediante las cuales \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0solicitaron el reconocimiento y pago de reliquidaci\u00f3n pensional, de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0indemnizaciones, de reajuste pensional, de indemnizaciones moratorias por no \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0cancelaci\u00f3n oportuna de prestaciones y por omisi\u00f3n en la pr\u00e1ctica del examen \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0m\u00e9dico de retiro, as\u00ed como la ejecuci\u00f3n de condenas decretadas mediante \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0providencias de la justicia laboral. \u00a0 \u00a0<\/p>\n<p>En seis de los procesos acumulados, los apoderados judiciales actuaron sin \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0poder. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Se concluy\u00f3 que \u201cno pod\u00edan los abogados en los casos bajo examen \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0atribuirse, sin poder, la facultad de agenciar los derechos de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0extrabajadores de Colpuertos, menos todav\u00eda si no se configuraba ejercicio \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de una agencia oficiosa, que ni ten\u00eda lugar, por cuanto faltaba el requisito \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de la indefensi\u00f3n de los solicitantes, ni fue puesta de presente en las \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0respectivas demandas, ni tampoco ratificada por los interesados\u201d (Se \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0destaca). \u00a0 \u00a0<\/p>\n<p>En consecuencia, la Corte compuls\u00f3 copias al Consejo Superior de la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Judicatura y a la Fiscal\u00eda General de la Naci\u00f3n para que investigaran la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0conducta de los abogados. \u00a0\u00a0<\/p>\n<p>T-531 de 2002 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>El abogado Alfredo Cano C\u00f3rdoba present\u00f3 acci\u00f3n de tutela bajo una doble \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0condici\u00f3n al expresar que actuaba como apoderado judicial y como agente \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0oficioso de la se\u00f1ora Gloria Mar\u00eda Portilla Cundar y de 63 personas m\u00e1s, \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0todos pensionados del Departamento de Nari\u00f1o. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>En esta oportunidad, la Corte indic\u00f3 que el principal efecto del acto de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0apoderamiento consiste en \u201cperfeccionar la legitimaci\u00f3n en la causa por \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0activa, por lo cual el juez de tutela estar\u00e1 en la obligaci\u00f3n, despu\u00e9s \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de constatar sus elementos, de proceder a pronunciarse de fondo sobre los \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0hechos y las pretensiones relacionados en el escrito de acci\u00f3n respectivo\u201d. \u00a0 \u00a0<\/p>\n<p>Al analizar el fondo del asunto, la Corte concluy\u00f3 que \u201cal no encontrarse \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0acreditada su calidad de apoderado judicial ante la inexistencia de poder \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0especial para el caso e igualmente al no encontrarse satisfechos los \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0requisitos para la existencia de la agencia oficiosa, no se configur\u00f3 la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0legitimaci\u00f3n en la causa por activa\u201d (Se destaca). \u00a0\u00a0<\/p>\n<p>T-658 de 2002 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>El se\u00f1or William Cohen Miranda, actuando en causa propia, interpuso acci\u00f3n \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de tutela el d\u00eda 31 de enero de 2002, por estimar vulnerados sus derechos \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0fundamentales a la igualdad y al debido proceso, como consecuencia de la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0actuaci\u00f3n de la Divisi\u00f3n Jur\u00eddica del Seguro Social &#8211; Seccional Bol\u00edvar, \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0entidad que al tramitar un proceso de cobro coactivo contra el se\u00f1or Ram\u00f3n \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Antonio Garc\u00eda Ortega, por falta de pago e incorrecta liquidaci\u00f3n de aportes \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0en seguridad social, desconoci\u00f3 &#8211; a juicio del accionante &#8211; palmaria y \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0abiertamente el ordenamiento jur\u00eddico. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>La falta de poder especial para adelantar el proceso \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de tutela por parte de un apoderado judicial, aun cuando tenga poder \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0espec\u00edfico o general en otros asuntos, no lo habilita para ejercer la acci\u00f3n \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de amparo constitucional a nombre de su mandante y, por lo tanto, en estos \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0casos, la tutela debe ser declarada improcedente ante la falta de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0legitimaci\u00f3n por activa (Negrillas adicionales). \u00a0 \u00a0<\/p>\n<p>En relaci\u00f3n con la acci\u00f3n de tutela de la referencia, el abogado William \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Cohen Miranda no acredit\u00f3 su condici\u00f3n de apoderado especial del se\u00f1or Ram\u00f3n \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Antonio Garc\u00eda Ortega, pues no anex\u00f3 al expediente el respectivo poder de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0representaci\u00f3n ni hizo manifiesta su intenci\u00f3n de agenciar derechos ajenos o \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de terceros. Por el contrario, aport\u00f3 un poder que le hab\u00eda sido conferido \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0para tramitar un proceso ordinario. \u00a0 \u00a0<\/p>\n<p>T-664 de 2011 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>La docente\u00a0 Ruby Esperanza Plazas Alvis, por medio de apoderado, \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0interpuso acci\u00f3n de tutela en contra de unas Secretar\u00edas de Educaci\u00f3n\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0por considerar vulnerados los derechos fundamentales\u00a0 a la familia, la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0salud,\u00a0 y la vida de su hija Aura Mar\u00eda Julieth Ostos Plazas (de 8 a\u00f1os \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de edad) y de su madre Aura Mar\u00eda Alvis (de 69), quienes se encuentran en \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0delicado estado de salud por lo que requieren un cuidado especial que no \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0puede brindar efectivamente dado que trabaja en un municipio distinto a la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0ciudad de Ibagu\u00e9 donde ellas habitan y acuden a controles m\u00e9dicos. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>En el caso concreto, \u201cse constata a folio 2 que la accionante acudi\u00f3 ante \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Notaria\u00a0 y present\u00f3 personalmente y para reconocimiento poder especial \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0para interponer la actual acci\u00f3n de tutela, documento que se presume \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0aut\u00e9ntico conforme al art\u00edculo 10 del Decreto 2591. Adicionalmente, \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0observado el expediente no consta formalmente la acreditaci\u00f3n de la calidad \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de abogado del representante judicial de la accionante, motivo por el que \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0fue declarada improcedente la presente acci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Dado que en este asunto se alega la presunta vulneraci\u00f3n de derechos \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0fundamentales de una ni\u00f1a y de una persona de avanzada edad que padecen \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0trastornos de salud, materializando el\u00a0 principio de la informalidad \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0propio de la acci\u00f3n de tutela y de la prevalencia del derecho sustancial, \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0el despacho del magistrado sustanciador procedi\u00f3 a consultar la p\u00e1gina \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0electr\u00f3nica de la rama judicial (www.ramajudicial.gov.co) y logr\u00f3 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0constatar que la tarjeta profesional del apoderado de la accionante se \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0encuentra inscrita en el registro de abogados y seg\u00fan el sistema est\u00e1 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0vigente\u201d \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0(Se destaca). \u00a0 \u00a0 \u00a0<\/p>\n<p>28. De conformidad con lo anterior, para esta Sala de Revisi\u00f3n resulta claro que \u00a0 la postura de la Corte Constitucional ha sido pac\u00edfica respecto de declarar la \u00a0 falta de legitimaci\u00f3n en la causa por activa, en aquellos eventos en los cuales \u00a0 se presenta una carencia de poder para formular acci\u00f3n de tutela por conducto de \u00a0 apoderado judicial, salvo en el \u00faltimo caso, en el cual, atendiendo el principio \u00a0 de informalidad de la tutela y la prevalencia del derecho sustancial, esta \u00a0 Corporaci\u00f3n procedi\u00f3 a constatar en la p\u00e1gina web de la Rama Judicial la \u00a0 inscripci\u00f3n de un abogado. \u00a0 \u00a0<\/p>\n<p>29. La anterior posici\u00f3n jurisprudencial, llevar\u00eda a que en este asunto, en \u00a0 principio, se confirmara la decisi\u00f3n del Juzgado Primero Civil del Circuito \u00a0 Especializado en Restituci\u00f3n de Tierras de Pereira de no conceder la impugnaci\u00f3n \u00a0 de la sentencia de primera instancia, por cuanto se configur\u00f3 una falta de \u00a0 legitimaci\u00f3n en la causa por activa, toda vez que la tarjeta profesional de la \u00a0 abogada Gloria Yobana Castro Torres se encontraba suspendida y, en esa medida, \u00a0 no cumple con uno de los requisitos del acto de apoderamiento relacionados en el \u00a0 p\u00e1rrafo 21 supra, como lo es, ser un profesional del derecho \u00a0 habilitado con tarjeta profesional. \u00a0 \u00a0<\/p>\n<p>30. Sin embargo, la Sala Primera de Revisi\u00f3n, en esta oportunidad, se apartar\u00e1 \u00a0 de esta postura jurisprudencial, dadas las particulares circunstancias que \u00a0 diferencian este asunto de los relacionados en el anterior cuadro, tal como a \u00a0 continuaci\u00f3n pasa a explicarse. \u00a0 \u00a0<\/p>\n<p>31. En efecto, el accionante se encuentra \u00a0 en una especial situaci\u00f3n de riesgo, como consecuencia de su carencia relativa \u00a0 de autonom\u00eda para satisfacer sus necesidades b\u00e1sicas hasta tanto agote la v\u00eda \u00a0 judicial ordinaria, comoquiera que: \u00a0 \u00a0<\/p>\n<p>i) Tiene 65 a\u00f1os de \u00a0 edad, por ende, pertenece a un grupo de especial protecci\u00f3n constitucional de \u00a0 las personas de la tercera edad, en los t\u00e9rminos de los art\u00edculos 46 superior[25], 7 de la Ley \u00a0 1276 de 2009[26] \u00a0y la jurisprudencia constitucional[27]. \u00a0 \u00a0<\/p>\n<p>ii) Se encuentra en \u00a0 condici\u00f3n de invalidez, debido a que fue calificado con una p\u00e9rdida de capacidad \u00a0 laboral del 52.54%, con fecha de estructuraci\u00f3n del 15 de febrero de 2016. \u00a0 \u00a0<\/p>\n<p>iii) Le fue \u00a0 diagnosticado un tumor maligno en el cerebro, con excepci\u00f3n de l\u00f3bulos y \u00a0 ventr\u00edculos. En el expediente obra copia de la correspondiente historia \u00a0 cl\u00ednica elaborada por la Cl\u00ednica Onc\u00f3logos del Occidente S.A., la cual da cuenta \u00a0 del cr\u00edtico estado de salud del se\u00f1or Lizardo Narv\u00e1ez Valencia, en los \u00a0 siguientes t\u00e9rminos: \u00a0 \u00a0<\/p>\n<p>\u201cNOTA DE EVOLUCI\u00d3N Y TRATAMIENTO DE CUIDADOS PALIATIVOS \u00a0 \u00a0<\/p>\n<p>Subjetivo \u00a0 \u00a0<\/p>\n<p>APERTURA DE FOLIO PARA MANEJO EN DOMICILIO. \u00a0 EMPEORAMIENTO DE LA MOVILIDAD DEL HEMICUERPO IZQUIERDO. \u00a0 \u00a0<\/p>\n<p>CUIDADO PALIATIVO. SEDE MARAYA MEGACENTRO. CONTROL. \u00a0 VALORACI\u00d3N M\u00c9DICA. \u00a0 \u00a0<\/p>\n<p>NOTA ONCOLOG\u00cdA: 17 ENE 2018. Historia de Cefalea de \u00a0 inicio reciente en noviembre de 2017 hasta insoportable. Se realiz\u00f3 im\u00e1genes que \u00a0 mostraron lesi\u00f3n temporal derecha. Se llev\u00f3 a cirug\u00eda con resecci\u00f3n completa y \u00a0 reporte AP: GLIOBASTOMA MULTIFORME. Evoluci\u00f3n POP satisfactoria. Es enviado a \u00a0 concepto. Se comenta ampliamente con paciente e hija sobre la necesidad de \u00a0 terapia adyuvante concomitante con quimioterapia + radioterapia. Se dan \u00a0 indicaciones y advertencias. Pron\u00f3stico adverso. Control en 3 semanas + \u00a0 reportes. URGENTE!!! RADIOTERAPIA TEMOZOLAMIDA. \u00a0 \u00a0<\/p>\n<p>16 FEB 2018: INMUNOHISTOQU\u00cdMICA MP-1239. ESTUDIOS \u00a0 COMPLEMENTARIOS DE INMUNOHISTOQU\u00cdMICA TUMOR CEREBRAL REGI\u00d3N TEMPOROOCCIPITAL \u00a0 DERECHA, LH713023: (\u2026). \u00a0 \u00a0<\/p>\n<p>FINALIZ\u00d3 RADIOTERAPIA 7\/7. CUADRO PSIC\u00d3TICO CON \u00a0 ANSIEDAD CON AGRESIVIDAD, GRITAR (sic) GOLPEANDO A LAS PERSONAS. \u00a0SUSPENDI\u00d3 LA DEXAMETASONA. QUETIAPINA 100 EN LA NOCHE Y 124 MGS EN EL D\u00cdA. NO \u00a0 USA HALOPERIDOL. CLONAZEPAM 12 GOTAS CADA 12 HORAS. NO EST\u00c1 CAMINANDO, CON \u00a0 GRAN INESTABILIDAD, ARRASTRA MUCHO EL PIE IZQUIERDO, CALAMBRE EN LA MANO \u00a0 DERECHA. SE QUEJA DE DOLOR EN EL PECHO. PERSISTE SENSACI\u00d3N DE AHOGO. REFIERE \u00a0 DOLOR Y OBSTRUCCI\u00d3N NASAL. ESTRE\u00d1IMIENTO DE TRES A 4 D\u00cdAS, SE QUEJA DE DOLOR \u00a0 MODERADO EN REGI\u00d3N DORSAL AMBULATORIO. ALPRAZOLAM 0.5. ESOMEPRAZOL 20 X 2. \u00a0 ACETAMINOFEN. FENITOINA 300 MGS. COME BIEN, DEPOSICIONES (sic). DUERME REGULAR. \u00a0 NO CONCILIA EL SUE\u00d1O. NO CONVULSION.ADA (sic). VIVE CON DOS ENFERMERAS LAS 24 \u00a0 HORAS. DUERME CON EL USO DE QUETIAPINA Y CLONAZEPAM. DESORIENTACI\u00d3N SEXUAL. \u00a0 ALTERACI\u00d3N DE LA AUDICI\u00d3N Y MOVILIDAD. DUERME CON LA BOCA ABIERTA Y OJOS \u00a0 ABIERTOS. RONCA. NO CONTROL DE ESF\u00cdNTERES. DUERME UNAS 4 HORAS. HABLA DE RABIA \u00a0 CON TAQUICARDIA. (\u2026). \u00a0 \u00a0<\/p>\n<p>An\u00e1lisis \u00a0 \u00a0<\/p>\n<p>SE CONTIN\u00daA EN CUIDADO PALIATIVO. AMBULATORIO, CONTROL \u00a0 DE S\u00cdNTOMAS. MANEJO DE LA DISNEA: SUSPENDIDO INHALADOR SALBUTAMOL CADA 8 HORAS E \u00a0 IPATROPIO. BECLOMETASONA NASAL PARA SINUSITIS. ALPRAZOLAM 0.5 CADA 12 HORAS. \u00a0 ANALG\u00c9SICA ACETAMINOF\u00c9N 500 MGS CADA 6 HORAS.\u00a0 \u00a0 \u00a0<\/p>\n<p>SE INICIA LEVETERACETAM 500 MGS CADA 12 HORAS. \u00a0 ESTEROIDES SUSPENDIDO. IA. ESOMEPRAZOL. \u00a0 \u00a0<\/p>\n<p>PACIENTE REQUIERE USO DIARIO DE 4 A 6 PA\u00d1ALES DIARIOS \u00a0 PARA DIGNIFICAR SU VIDA, EVITAR LESIONES EN PIEL Y MANEJO FUNCIONAL DEL \u00a0 PACIENTE, YA QUE PRESENTA INCONTINENCIA VESICAL Y RECTAL POR SU ENFERMEDAD. SE \u00a0 BENEFICIAR\u00cdA DE ESTAR EN PROGRAMA DE PACIENTE CR\u00d3NICO POR LA EPS. \u00a0 \u00a0<\/p>\n<p>Plan tratamiento \u00a0 \u00a0<\/p>\n<p>CUIDADO PALIATIVO, AMBULATORIO, CONTROL DE S\u00cdNTOMAS, \u00a0 MANEJO DE LA DISNEA: QUETAPINA 100 MGS CADA 12 HORAS Y 25 MGS EN LA NOCHE (TOTAL \u00a0 ALPRAZOLAM 0.5 GOTAS CADA 12 HORAS. LEVETIRACETAM 500 MGS CADA 12 HORAS. \u00a0 PROTECCI\u00d3N G\u00c1STRICA ENEMA ORAL). \u00a0 \u00a0<\/p>\n<p>PACIENTE REQUIERE USO DIARIO DE 4 A 6 PA\u00d1ALES DIARIOS \u00a0 PARA DIGNIFICAR SU VIDA, EVITAR LAS LESIONES EN PIEL Y MANEJO FUNCIONAL DEL \u00a0 PACIENTE, YA QUE PRESENTA INCONTINENCIA VESICAL Y RECTAL POR SU ENFERMEDAD. USAR (sic) CAMA \u00a0 HOSPITALARIA PARA MEJOR MANEJO DEL PACIENTE. (\u2026). \u00a0 \u00a0<\/p>\n<p>\u00cdNDICE DE BARTHEL INFERIOR 40 DE 100, COMIDA \u00a0 DEPENDIENTE, ASEO DEPENDIENTE, VESTIDO DEPENDIENTE, ARREGLO DEPENDIENTE, \u00a0 DEPOSICI\u00d3N (sic) ACCIDENTE OCASIONAL, MICCI\u00d3N (sic) ACCIDENTE OCASIONAL, IR BA\u00d1O \u00a0 (sic) NECESITA AYUDA, TRASLADO DEPENDIENTE, DEAMBULACI\u00d3N DEPENDIENTE, \u00a0 ESCALERAS DEPENDIENTE 15 DE 100. DEPENDENCIA TOTAL\u201d[28]. \u00a0 \u00a0<\/p>\n<p>iv) Fue beneficiario \u00a0 del Programa Nacional de Alimentaci\u00f3n para el Adulto Mayor \u201cJuan Luis Londo\u00f1o\u201d[29], sin embargo \u00a0 fue desafiliado en el a\u00f1o 2011, tal como se afirma en la demanda de tutela[30]. \u00a0 \u00a0<\/p>\n<p>v) Una vez consultada \u00a0 la p\u00e1gina web del SISB\u00c9N, esta Sala observ\u00f3 que el tutelante tiene un puntaje de \u00a0 14,09[31]. \u00a0 El ingreso de este ciudadano al sistema de salud fue el 23 de febrero de 2012. \u00a0 Es beneficiario en salud por parte de su hija Stefany Narv\u00e1ez[32]. \u00a0 \u00a0<\/p>\n<p>32. De conformidad con lo anterior, esta Sala de Revisi\u00f3n observa que el actual \u00a0 estado de salud del se\u00f1or Lizardo Narv\u00e1ez Valencia es cr\u00edtico, habida \u00a0 consideraci\u00f3n de que su capacidad de locomoci\u00f3n es limitada y, por ende, \u00a0 requiere de la ayuda de terceros para poder desplazarse. Adem\u00e1s, padece de \u00a0 incontinencia vesical y rectal, por lo que requiere del uso continuo de pa\u00f1ales, \u00a0 de 4 a 6 diarios. Como si lo anterior fuera poco, se indic\u00f3 en la historia \u00a0 cl\u00ednica que el accionante presenta un cuadro psic\u00f3tico con ansiedad y \u00a0 agresividad. \u00a0 \u00a0<\/p>\n<p>33. De otro lado, en lo que tiene que ver con la conducta de la abogada, esta \u00a0 Sala observa que dentro del expediente no existe constancia alguna que d\u00e9 cuenta \u00a0 de que el se\u00f1or Lizardo Narv\u00e1ez Valencia tuviera conocimiento de que la abogada \u00a0 Gloria Yobana Castro Torres ten\u00eda su tarjeta profesional suspendida. Adem\u00e1s que \u00a0 resulta desde todo punto de vista desproporcionado, trasladarle esa carga al \u00a0 accionante, por lo que, por el contrario al otorgarle poder a la se\u00f1ora Gloria \u00a0 Yobana, actu\u00f3 bajo el principio de la buena fe, esto es, con la \u201cconfianza, seguridad y credibilidad\u201d[33] \u00a0de que dicha profesional era una abogada en \u00a0 ejercicio. \u00a0 \u00a0<\/p>\n<p>34. En l\u00ednea con lo anterior, no debe \u00a0 perderse de vista que la falta de legitimaci\u00f3n en la causa por activa que \u00a0 deber\u00eda declararse en este asunto, no fue originada por el se\u00f1or Lizardo Narv\u00e1ez \u00a0 Valencia, por lo tanto no resulta razonable aplicar esta consecuencia jur\u00eddica \u00a0 en el presente asunto, en tanto que la conducta reprochable de la abogada no le \u00a0 es imputable al tutelante. \u00a0 \u00a0<\/p>\n<p>35. De igual forma, no se debe dejar pasar desapercibido que, desde el momento \u00a0 de la presentaci\u00f3n de la acci\u00f3n de tutela, la abogada aludida ya ten\u00eda su \u00a0 tarjeta profesional suspendida, situaci\u00f3n que no fue advertida por el juez de \u00a0 tutela en el auto admisorio de dicha acci\u00f3n constitucional, sino hasta el \u00a0 momento en que se pronunci\u00f3 acerca de la concesi\u00f3n de la impugnaci\u00f3n formulada \u00a0 por la apoderada. En esta medida, tambi\u00e9n es reprochable que el juez no haya \u00a0 advertido esta situaci\u00f3n desde la fase inicial del proceso de tutela, lo que dio \u00a0 lugar a que el tutelante no tuviera la posibilidad de tomar medida alguna para \u00a0 evitar las consecuencias procesales por la actuaci\u00f3n irregular de la abogada. \u00a0 \u00a0<\/p>\n<p>36. Advertidas tales circunstancias, la \u00a0 Sala considera que la eventual declaratoria de improcedencia de esta acci\u00f3n de \u00a0 tutela, har\u00eda m\u00e1s gravosa la situaci\u00f3n del tutelante, por cuanto, probablemente, \u00a0 se ver\u00eda obligado a presentar una nueva solicitud de amparo a fin de obtener el \u00a0 reconocimiento de su derecho pensional. \u00a0 \u00a0<\/p>\n<p>37. As\u00ed las cosas, en virtud de los \u00a0 principios de sumariedad, celeridad e informalidad[34] que \u00a0 orientan el procedimiento de tutela, como condici\u00f3n necesaria para la protecci\u00f3n \u00a0 real y oportuna de los derechos fundamentales, y en atenci\u00f3n a las \u00a0 circunstancias especiales del caso, de manera excepcional esta Sala de Revisi\u00f3n \u00a0 asumir\u00e1 que acci\u00f3n de tutela fue interpuesta por la se\u00f1ora Gloria Yobana Castro \u00a0 Torres en calidad de agente oficiosa del se\u00f1or Lizardo Narv\u00e1ez Valencia. \u00a0 \u00a0<\/p>\n<p>2.2. Legitimaci\u00f3n en la causa[35] \u00a0 \u00a0<\/p>\n<p>38. El presente caso cumple con el requisito de legitimaci\u00f3n en la causa por \u00a0 activa, dado que la acci\u00f3n de tutela fue ejercida por el se\u00f1or Lizardo Narv\u00e1ez \u00a0 Valencia, mediante agencia oficiosa de la se\u00f1ora Gloria Yobana Castro Torres, al \u00a0 considerar vulnerado su derecho fundamental a la seguridad social, vida digna y \u00a0 m\u00ednimo vital, como consecuencia de la negativa de Colpensiones a reconocer su \u00a0 pensi\u00f3n de invalidez. \u00a0 \u00a0<\/p>\n<p>2.3. Subsidiariedad \u00a0 \u00a0<\/p>\n<p>40. La protecci\u00f3n de los derechos constitucionales fundamentales no es un asunto \u00a0 reservado a la acci\u00f3n de tutela. Con fundamento en la obligaci\u00f3n que el art\u00edculo \u00a0 2 de la Constituci\u00f3n impone a las autoridades de la Rep\u00fablica, de proteger a \u00a0 todas las personas en sus derechos y libertades, los distintos mecanismos \u00a0 judiciales previstos en la ley han sido establecidos para garantizar la vigencia \u00a0 de los derechos constitucionales, incluidos los de car\u00e1cter fundamental. De ah\u00ed \u00a0 que la Constituci\u00f3n defina la tutela como un mecanismo subsidiario frente a los \u00a0 dem\u00e1s medios de defensa judicial, los cuales son, entonces, los instrumentos \u00a0 preferentes a los que deben acudir las personas para lograr la protecci\u00f3n de sus \u00a0 derechos, tal como disponen el inciso 3\u00ba del art\u00edculo 86 de la Constituci\u00f3n \u00a0 Pol\u00edtica, el numeral 1 del art\u00edculo 6 y el inciso 1\u00b0 del art\u00edculo 8 del \u00a0 Decreto-ley 2591 de 1991. De estas disposiciones se infieren los siguientes \u00a0 cuatro postulados, en relaci\u00f3n con el car\u00e1cter subsidiario de la acci\u00f3n de \u00a0 tutela: \u00a0 \u00a0<\/p>\n<p>41. \u00a0i) La acci\u00f3n de tutela debe proceder de forma directa y definitiva \u00a0 cuando no exista otro medio o recurso de defensa judicial que garantice \u00a0 la protecci\u00f3n de los derechos constitucionales fundamentales. De existir otro \u00a0 medio o recurso de defensa judicial, primero, se debe determinar si fue \u00a0 interpuesto y resuelto por la autoridad judicial competente o, segundo, en caso \u00a0 de que no se hubiese agotado, determinar su existencia formal en el caso \u00a0sub examine. \u00a0 \u00a0<\/p>\n<p>42. \u00a0ii) En caso de ineficacia, como consecuencia de la \u00a0 situaci\u00f3n de vulnerabilidad del accionante, la tutela debe proceder \u00a0 de manera definitiva. El juez de tutela debe determinar la eficacia en \u00a0 concreto (y no meramente formal o abstracta) de los otros medios o \u00a0 recursos de defensa. Lo anterior, en los t\u00e9rminos del apartado final del numeral \u00a0 1 del art\u00edculo 6 del Decreto 2591 de 199122, y en la medida en que el \u00a0 lenguaje constitucional apunta a valorar la efectividad del medio de defensa en \u00a0 relaci\u00f3n con las condiciones del individuo. \u00a0 \u00a0<\/p>\n<p>43. \u00a0iii) La tutela debe proceder de manera transitoria \u00a0siempre que se acredite un supuesto de perjuicio irremediable. \u00a0 \u00a0<\/p>\n<p>44. \u00a0iv) En caso de no acreditarse una situaci\u00f3n de vulnerabilidad \u00a0como tampoco un supuesto de perjuicio irremediable la acci\u00f3n de tutela \u00a0 debe declararse improcedente23, dada la eficacia en \u00a0 concreto del medio judicial principal y la inexistencia de una situaci\u00f3n \u00a0 inminente, urgente, \u00a0grave e impostergable que amerite su otorgamiento transitorio. \u00a0 \u00a0<\/p>\n<p>45. Ahora bien, en aquellos eventos en los que el problema jur\u00eddico sustancial \u00a0 del caso supone el an\u00e1lisis del principio de la condici\u00f3n m\u00e1s beneficiosa, para \u00a0 efectos del reconocimiento y pago de la pensi\u00f3n de invalidez, la Corte \u00a0 Constitucional, en sentencia SU-442 de 2016, indic\u00f3 que la solicitud de amparo \u00a0 es procedente si se emplea cuando i) el actor no dispone de otro \u00a0 medio judicial de defensa; o ii) existen otros medios de defensa \u00a0 judicial pero es necesaria la tutela para evitar la consumaci\u00f3n de un perjuicio \u00a0 irremediable; o iii) los recursos disponibles no son id\u00f3neos o \u00a0 eficaces, toda vez que su sola existencia formal no es garant\u00eda de su utilidad \u00a0 en el caso concreto. En esa medida, destac\u00f3 que es competencia del juez \u00a0 constitucional examinar cu\u00e1l es la eficacia que, en concreto, tiene el otro \u00a0 instrumento de protecci\u00f3n, para lo cual, se debe verificar si \u201clos otros \u00a0 medios de defensa proveen un remedio integral y si son expeditos para evitar un \u00a0 perjuicio irremediable\u201d. \u00a0 \u00a0<\/p>\n<p>46. Al descender al caso concreto, esta Sala de Revisi\u00f3n observa que el se\u00f1or \u00a0 Lizardo Narv\u00e1ez Valencia ha pretendido, en dos oportunidades diferentes, la \u00a0 obtenci\u00f3n de su pensi\u00f3n de invalidez, no obstante, hasta la fecha no ha obtenido \u00a0 el reconocimiento respectivo. En efecto, Colpensiones, mediante las Resoluciones \u00a0 GNR 376868 de diciembre 9 de 2016 y SUB 65297 de mayo 15 de 2017, neg\u00f3 el \u00a0 derecho pensional aludido, sin embargo, tales decisiones no fueron \u00a0 controvertidas ante la sede administrativa, ni mucho menos por la v\u00eda ordinaria. \u00a0 \u00a0<\/p>\n<p>47. A continuaci\u00f3n se destacan, de manera cronol\u00f3gica, las distintas actuaciones \u00a0 administrativas realizadas con ocasi\u00f3n de las m\u00faltiples solicitudes elevadas por \u00a0 el se\u00f1or Lizardo Narv\u00e1ez Valencia ante la entidad administradora de pensiones \u00a0 aludida. \u00a0 \u00a0<\/p>\n<p>Primera solicitud (2014) \u00a0 \u00a0<\/p>\n<p>&#8211; El 17 de julio de \u00a0 2014, el Instituto de Seguros Sociales dict\u00f3 la Resoluci\u00f3n GNR No. 262094, en \u00a0 cuya virtud neg\u00f3 la pensi\u00f3n de vejez e indemnizaci\u00f3n sustitutiva de vejez, por \u00a0 cuanto encontr\u00f3 que el solicitante no cumpl\u00eda con los requisitos exigidos para \u00a0 tal reconocimiento[36]. \u00a0 \u00a0<\/p>\n<p>&#8211; \u00a0El \u00a0 anterior acto administrativo fue confirmado mediante la Resoluci\u00f3n VPB 17427 de \u00a0 8 de octubre de 2014[37]. \u00a0 \u00a0<\/p>\n<p>Segunda solicitud (2016) \u00a0 \u00a0<\/p>\n<p>&#8211; \u00a0El \u00a0 24 de mayo de 2016, el Instituto de Seguros Sociales profiri\u00f3 la Resoluci\u00f3n GNR \u00a0 No. 151096, por medio de la cual neg\u00f3 la indemnizaci\u00f3n sustitutiva de vejez, \u00a0 debido a que el se\u00f1or Narv\u00e1ez Valencia no cumpl\u00eda con los requisitos exigidos \u00a0 para tal reconocimiento[38]. \u00a0 \u00a0<\/p>\n<p>Tercera solicitud (2016) \u00a0 \u00a0<\/p>\n<p>&#8211; \u00a0El \u00a0 23 de noviembre de 2016, el se\u00f1or Lizardo Narv\u00e1ez Valencia requiri\u00f3 a \u00a0 Colpensiones el reconocimiento y pago de su pensi\u00f3n de invalidez[39]. \u00a0 \u00a0<\/p>\n<p>&#8211; El 9 de diciembre de 2016, Colpensiones profiri\u00f3 la Resoluci\u00f3n 376868, \u00a0 mediante la cual neg\u00f3 el reconocimiento solicitado, toda vez que dicho ciudadano \u00a0 no demostr\u00f3 un n\u00famero m\u00ednimo de 50 semanas cotizadas dentro de los tres a\u00f1os \u00a0 anteriores a la fecha de estructuraci\u00f3n de la invalidez, para lo cual, explic\u00f3 \u00a0 que &#8220;del 15 de febrero de 2013 al 15 de febrero de 2016 (fecha de \u00a0 estructuraci\u00f3n) no se efectuaron cotizaciones al Sistema de Seguridad Social en \u00a0 Pensiones de conformidad con lo observado en el aplicativo de historia laboral \u00a0 de esta entidad\u201d[40]. \u00a0 \u00a0<\/p>\n<p>Cuarta solicitud (2017) \u00a0 \u00a0<\/p>\n<p>&#8211; \u00a0El \u00a0 23 de marzo de 2017, el se\u00f1or Lizardo Narv\u00e1ez Valencia requiri\u00f3 nuevamente a \u00a0 Colpensiones el reconocimiento y pago de su pensi\u00f3n de invalidez[41]. \u00a0 \u00a0<\/p>\n<p>48. A partir de este recuento cronol\u00f3gico, para esta Sala de Revisi\u00f3n no hay \u00a0 asomo de duda de que desde el a\u00f1o 2014 el se\u00f1or Lizardo Narv\u00e1ez \u00a0 Valencia ha pretendido, en cuatro oportunidades diferentes, la obtenci\u00f3n de su \u00a0 pensi\u00f3n de vejez, la indemnizaci\u00f3n sustitutiva de vejez e invalidez, sin \u00a0 embargo, hasta la fecha no ha logrado su cometido. En esa medida, en principio, \u00a0 esta acci\u00f3n de tutela no cumplir\u00eda con el requisito de subsidiariedad, debido a \u00a0 que el tutelante contaba con los mecanismos propios de la jurisdicci\u00f3n ordinaria \u00a0 para reclamar su reconocimiento pensional. A lo cual, se agrega que el tutelante \u00a0 no esgrimi\u00f3 raz\u00f3n alguna que justificara por qu\u00e9 no acudi\u00f3 a la v\u00eda ordinaria \u00a0 durante todo este tiempo. \u00a0 \u00a0<\/p>\n<p>49. A pesar de la circunstancia advertida, la Sala estima que la solicitud de \u00a0 amparo del se\u00f1or Lizardo Narv\u00e1ez Valencia debe proceder, de manera definitiva, \u00a0debido a que se encuentra plenamente acreditada la situaci\u00f3n de \u00a0 vulnerabilidad del tutelante, tal como se explic\u00f3 en el ac\u00e1pite de cuesti\u00f3n \u00a0 previa del numeral 2.1. Lo anterior, a fin de evitar la ocurrencia de un \u00a0 perjuicio irremediable. \u00a0 \u00a0<\/p>\n<p>2.4. Inmediatez \u00a0 \u00a0<\/p>\n<p>50. La definici\u00f3n acerca de cu\u00e1l es el t\u00e9rmino \u201crazonable\u201d \u00a0 que debe mediar entre la fecha de ocurrencia de la presunta afectaci\u00f3n de los \u00a0 derechos fundamentales y su cuestionamiento en sede de tutela no ha sido \u00a0 pac\u00edfica en la jurisprudencia. Por tal raz\u00f3n, de manera abstracta y previa, este \u00a0 solo puede catalogarse como prima facie, pues su valoraci\u00f3n concreta est\u00e1 \u00a0 sujeta a las circunstancias espec\u00edficas del caso, a las condiciones del \u00a0 tutelante (en especial a su situaci\u00f3n de vulnerabilidad), a los intereses \u00a0 jur\u00eddicos creados a favor de terceros por la actuaci\u00f3n que se cuestiona y a la \u00a0 jurisprudencia constitucional en casos an\u00e1logos. \u00a0 \u00a0<\/p>\n<p>51. Ahora bien, la Corte Constitucional, en la sentencia SU-442 de 2016, destac\u00f3 \u00a0 la necesidad de que \u201cla acci\u00f3n sea interpuesta de manera oportuna en relaci\u00f3n \u00a0 con el acto que gener\u00f3 la presunta vulneraci\u00f3n\u201d, habida consideraci\u00f3n \u00a0 de que el requisito de inmediatez encuentra su raz\u00f3n de ser en la tensi\u00f3n \u00a0 existente entre el derecho constitucional a presentar acci\u00f3n de tutela \u201cen \u00a0 todo momento\u201d y el deber de respeto de la acci\u00f3n como herramienta para la \u00a0 protecci\u00f3n inmediata de los derechos fundamentales. En otras palabras, pese a \u00a0 que la tutela no cuenta con un t\u00e9rmino de prescripci\u00f3n, ello no soslaya la \u00a0 necesaria correspondencia entre la naturaleza expedita de la acci\u00f3n y su \u00a0 oportuna presentaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>52. Adem\u00e1s, sostuvo que \u201cel juez constitucional debe ser m\u00e1s flexible al \u00a0 estudiar la procedibilidad cuando el actor es un sujeto de especial protecci\u00f3n, \u00a0 o cuando se encuentra en una situaci\u00f3n de debilidad manifiesta\u201d, pues en \u00a0 desarrollo del derecho fundamental a la igualdad es necesario otorgar un \u00a0 tratamiento diferencial positivo a aquellas personas que no se encuentran en \u00a0 capacidad de soportar las cargas y tiempos procesales que imponen los medios \u00a0 ordinarios de defensa, por representar, adem\u00e1s, la amenaza de un perjuicio \u00a0 irremediable a sus garant\u00edas ius fundamentales. Sobre todo, teniendo en \u00a0 cuenta que el reconocimiento de la pensi\u00f3n de invalidez, a pesar de ser una \u00a0 prestaci\u00f3n econ\u00f3mica de orden legal, puede comprometer derechos fundamentales de \u00a0 sujetos que por sus particulares condiciones de vulnerabilidad o debilidad \u00a0 manifiesta, son sujetos de especial protecci\u00f3n constitucional. \u00a0 \u00a0<\/p>\n<p>53. A su turno, la Corte Constitucional, en sentencia SU-442 de 2016, precis\u00f3 \u00a0 que el an\u00e1lisis de procedibilidad de la acci\u00f3n de tutela deb\u00eda ser m\u00e1s flexible en aquellos eventos en los que el actor \u00a0 es un sujeto de especial protecci\u00f3n, o cuando se encuentra en una situaci\u00f3n de \u00a0 debilidad manifiesta. En la misma providencia, indic\u00f3 que \u201cen desarrollo del \u00a0 derecho fundamental a la igualdad, le debe ofrecer un tratamiento diferencial \u00a0 positivo y analizar los requisitos de subsidiariedad e inmediatez desde una \u00a0 \u00f3ptica menos estricta, pues en estos casos el actor no puede soportar las cargas \u00a0 y los tiempos procesales que le imponen los medios ordinarios de defensa \u00a0 judicial de la misma manera que el resto de la sociedad\u201d. \u00a0Concluy\u00f3 que en los \u00a0 asuntos de pensi\u00f3n de invalidez, \u201clas diferentes Salas de Revisi\u00f3n han \u00a0 sostenido que la pensi\u00f3n puede pasar de ser una prestaci\u00f3n social de orden \u00a0 legal, a convertirse en un derecho fundamental inalienable, en especial cuando \u00a0 se trata de un sujeto de especial protecci\u00f3n constitucional o en condiciones de \u00a0 debilidad manifiesta\u201d. \u00a0 \u00a0<\/p>\n<p>54. Ahora bien, en este asunto se tiene que \u00a0 la acci\u00f3n de tutela fue presentada (6 de junio de 2018) un a\u00f1o despu\u00e9s de \u00a0 haberse dictado el acto administrativo que neg\u00f3 el reconocimiento pensional al \u00a0 se\u00f1or Lizardo Narv\u00e1ez Valencia (15 de mayo de 2017), circunstancia que prima \u00a0 facie llevar\u00eda a concluir que ha transcurrido un plazo amplio entre estos \u00a0 dos momentos, m\u00e1xime porque en la solicitud de amparo no se justific\u00f3 la causa \u00a0 de dicha demora. \u00a0 \u00a0<\/p>\n<p>55. Sin embargo, atendiendo las \u00a0 consideraciones previstas en la sentencia SU-442 de 2016 y el estado de \u00a0 debilidad manifiesta del tutelante que, adem\u00e1s, pertenece a un grupo de especial \u00a0 protecci\u00f3n constitucional de las personas de la tercera edad[43], esta Sala de \u00a0 Revisi\u00f3n considera que se encuentra satisfecho el requisito de inmediatez. \u00a0 \u00a0<\/p>\n<p>3. An\u00e1lisis del problema jur\u00eddico sustancial \u00a0 \u00a0<\/p>\n<p>56. El tutelante aleg\u00f3 la vulneraci\u00f3n de sus derechos fundamentales a la \u00a0 seguridad social, vida digna y m\u00ednimo vital, debido a que le neg\u00f3 el \u00a0 reconocimiento de su pensi\u00f3n de invalidez. Se adujo en el escrito de tutela que \u00a0 el se\u00f1or Lizardo Narv\u00e1ez Valencia tiene derecho a tal reconocimiento, en tanto \u00a0 que \u201ccotiz\u00f3 antes de la entrada en vigencia de la Ley 100 de 1993, muchas m\u00e1s \u00a0 de las trescientas (300) semanas que exige el mencionado Acuerdo 049\u201d[44]. \u00a0 \u00a0<\/p>\n<p>57. Al satisfacer la acci\u00f3n los requisitos de procedibilidad, esta Sala de \u00a0 Revisi\u00f3n debe resolver el siguiente problema jur\u00eddico sustancial: si \u00a0 Colpensiones vulner\u00f3 el derecho fundamental a la seguridad social, vida digna y \u00a0 m\u00ednimo vital, al no haber dado aplicaci\u00f3n al Acuerdo 049 de 1990, con fundamento \u00a0 en el principio de la condici\u00f3n m\u00e1s beneficiosa, para efectos de analizar la \u00a0 procedencia del reconocimiento y pago de la pensi\u00f3n de invalidez a favor del \u00a0 accionante. \u00a0 \u00a0<\/p>\n<p>3.1. Aplicaci\u00f3n del principio de la condici\u00f3n m\u00e1s beneficiosa en pensi\u00f3n de \u00a0 invalidez \u00a0 \u00a0<\/p>\n<p>58. Previo a abordar el an\u00e1lisis de fondo, esta Sala de Revisi\u00f3n estima \u00a0 pertinente hacer referencia a la ratio decidendi de la sentencia SU-442 \u00a0 de 2016, en la que se ajustaron\u00a0las reglas de aplicaci\u00f3n del principio de la \u00a0 condici\u00f3n m\u00e1s beneficiosa en materia de pensi\u00f3n de invalidez. Posteriormente, se \u00a0 realizar\u00e1 un ejercicio de subsunci\u00f3n de las condiciones f\u00e1cticas y normativas \u00a0 del caso en las reglas de unificaci\u00f3n de la mencionada providencia judicial. \u00a0 \u00a0<\/p>\n<p>59. En primer lugar, debe se\u00f1alarse que el principio de la condici\u00f3n m\u00e1s \u00a0 beneficiosa es un l\u00edmite de raigambre constitucional, en cuya virtud las \u00a0 expectativas leg\u00edtimas contra\u00eddas antes de la entrada en vigencia de la Ley 100 \u00a0 de 1993, deben ser respetadas frente a la entrada en vigor de una nueva norma. \u00a0 Este principio se constituye como una barrera que limita la competencia del \u00a0 legislador para \u201cagravar los requisitos ya cumplidos mediante reformas \u00a0 desprovistas de reg\u00edmenes de transici\u00f3n\u201d y es \u201coponible a la reforma \u00a0 introducida por la Ley 100 de 1993, en su versi\u00f3n original, e incluso por la Ley \u00a0 860 de 2003\u201d[45]. \u00a0 \u00a0<\/p>\n<p>60. El referido principio de la condici\u00f3n m\u00e1s beneficiosa permite analizar la \u00a0 solicitud de reconocimiento pensional de una persona, con fundamento en normas \u00a0 anteriores, e incluso derogadas, a aquella vigente y en principio aplicable al \u00a0 momento en que se estructur\u00f3 la invalidez respectiva. \u00a0 \u00a0<\/p>\n<p>61. En efecto, esta es la postura adoptada por esta Corporaci\u00f3n a partir de la \u00a0 sentencia SU-442 de 2016. En aquella oportunidad, se precis\u00f3 que \u201cla \u00a0 jurisprudencia de la Corte Constitucional ha sostenido que\u00a0no solo la norma \u00a0 pensional vigente (Ley 860 de 2003) o la inmediatamente anterior (Ley 100 de \u00a0 1993), sino incluso la antecedente a esta \u00faltima (Decreto 758 de 1990), puede \u00a0 aplicarse a una solicitud de pensi\u00f3n de invalidez, en la medida en que la \u00a0 persona haya cumplido con la densidad de semanas de cotizaci\u00f3n previstas en este \u00a0 \u00faltimo antes de expirar su periodo de vigencia\u201d. \u00a0 \u00a0<\/p>\n<p>62. Es as\u00ed como, para determinar si el principio de la condici\u00f3n m\u00e1s beneficiosa \u00a0 es aplicable para el estudio de una solicitud de pensi\u00f3n de invalidez, se \u00a0 requiere acudir a la siguiente regla. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Regla de aplicaci\u00f3n del principio de la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0condici\u00f3n m\u00e1s beneficiosa para el reconocimiento y pago de pensi\u00f3n de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0invalidez \u00a0 \u00a0<\/p>\n<p>(Sentencia SU-442 de 2016) \u00a0\u00a0<\/p>\n<p>1. El principio de la condici\u00f3n m\u00e1s \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0beneficiosa se extiende a todo el esquema normativo anterior \u00a0 \u00a0bajo cuyo amparo el afiliado o beneficiario haya contra\u00eddo una expectativa \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0leg\u00edtima. \u00a0\u00a0<\/p>\n<p>2. El afiliado debe haber reunido las \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0semanas de cotizaci\u00f3n exigidas por la norma que pretende le sea aplicada, \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0antes de la entrada en vigencia de la nueva disposici\u00f3n que modific\u00f3 los \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0requisitos para acceder el derecho pensional. \u00a0 \u00a0 \u00a0<\/p>\n<p>63. Ahora bien, con relaci\u00f3n a la aplicaci\u00f3n de normas anteriores a aquella bajo \u00a0 la cual se estructur\u00f3 el riesgo a ser amparado por la prestaci\u00f3n solicitada, la \u00a0 jurisprudencia constitucional fij\u00f3 la siguiente subregla: \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Subregla para el reconocimiento de la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0pensi\u00f3n de invalidez en aplicaci\u00f3n del Acuerdo 049 de 1990, por virtud del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0principio de la condici\u00f3n m\u00e1s beneficiosa \u00a0\u00a0<\/p>\n<p>El afiliado debe acreditar 300 semanas de cotizaci\u00f3n en cualquier tiempo, \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0antes del 1\u00b0 de abril de 1994, fecha de entrada en vigencia de la Ley 100 de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a01993. \u00a0 \u00a0 \u00a0<\/p>\n<p>64. Dado que el caso del tutelante se enmarca en el supuesto f\u00e1ctico objeto de \u00a0 unificaci\u00f3n, es aplicable la subregla para el reconocimiento de la pensi\u00f3n de \u00a0 invalidez del Acuerdo 049 de 1990, tal como a continuaci\u00f3n pasa a explicarse. \u00a0 \u00a0<\/p>\n<p>65. En efecto, el se\u00f1or Lizardo Narv\u00e1ez Valencia fue calificado con una p\u00e9rdida \u00a0 de capacidad laboral del 52.54%, con fecha de estructuraci\u00f3n del 15 de febrero \u00a0 de 2016. Para el momento de la p\u00e9rdida de capacidad laboral, hab\u00eda efectuado \u00a0 aportes por un total de 3.516 d\u00edas, es decir, 502 semanas, discriminadas as\u00ed: \u00a0 \u00a0<\/p>\n<p>ENTIDAD LABOR\u00d3 (Sic) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>DESDE \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>HASTA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>NOVEDAD \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>D\u00cdAS \u00a0\u00a0<\/p>\n<p>JOS\u00c9 F AR\u00c9VALO C Y C\u00cdA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1974\/03\/10 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1974\/11\/30 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>TIEMPO SERVICIOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>266 \u00a0\u00a0<\/p>\n<p>JOS\u00c9 F AR\u00c9VALO C Y C\u00cdA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1974\/12\/01 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1976\/03\/31 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>TIEMPO SERVICIOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>487 \u00a0\u00a0<\/p>\n<p>JOS\u00c9 F AR\u00c9VALO C Y C\u00cdA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1976\/04\/01 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1977\/05\/20 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>TIEMPO SERVICIOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>415 \u00a0\u00a0<\/p>\n<p>JOS\u00c9 F AR\u00c9VALO C Y C\u00cdA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1977\/09\/20 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1978\/09\/30 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>TIEMPO SERVICIOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>376 \u00a0\u00a0<\/p>\n<p>JOS\u00c9 F AR\u00c9VALO C Y C\u00cdA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1978\/10\/01 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1979\/07\/01 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>TIEMPO SERVICIOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>274 \u00a0\u00a0<\/p>\n<p>JOS\u00c9 F AR\u00c9VALO C Y C\u00cdA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1979\/10\/22 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1980\/12\/31 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>TIEMPO SERVICIOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>437 \u00a0\u00a0<\/p>\n<p>JOS\u00c9 F AR\u00c9VALO C Y C\u00cdA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1981\/01\/01 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1983\/12\/31 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>TIEMPO SERVICIOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1095 \u00a0\u00a0<\/p>\n<p>1 AUTONAL DE RISARALDA LTDA. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1988\/11\/01 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1998\/12\/31 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>TIEMPO SERVICIOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>61 \u00a0\u00a0<\/p>\n<p>1 AUTONAL DE RISARALDA LTDA. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1989\/01\/01 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1989\/02\/28 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>59 \u00a0\u00a0<\/p>\n<p>1 AUTONAL DE RISARALDA LTDA. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1989\/03\/01 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1989\/04\/15 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>TIEMPO SERVICIOS \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>46 \u00a0 \u00a0 \u00a0<\/p>\n<p>66. De acuerdo a lo anterior, la Sala encuentra que en este caso la solicitud de \u00a0 pensi\u00f3n de invalidez del se\u00f1or Lizardo Narv\u00e1ez Valencia debe analizarse conforme \u00a0 a los lineamientos fijados por esta Corporaci\u00f3n en la sentencia SU-442 de 2016, \u00a0 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Condici\u00f3n para aplicaci\u00f3n del Acuerdo 049 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de 1990 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Situaci\u00f3n pensional del tutelante \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Cumple \u00a0\u00a0<\/p>\n<p>Que el afiliado acredite, al 1\u00ba de abril de 1994, la densidad de 300 \u00a0 \u00a0semanas de cotizaci\u00f3n de que trata el art\u00edculo 6\u00ba del Acuerdo 049 de 1990. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Al 1\u00ba de abril de 1994, el afiliado hab\u00eda cotizado 3.516 d\u00edas, esto es,\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0502 \u00a0 \u00a0semanas. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>SI. El tutelante acredit\u00f3 m\u00e1s de 300 semanas de cotizaci\u00f3n en cualquier \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0tiempo, antes de la entrada en vigencia de la Ley 100 de 1993. \u00a0 \u00a0 \u00a0<\/p>\n<p>67. Ahora bien, de conformidad con la Resoluci\u00f3n GNR 376868 de 9 de diciembre de \u00a0 2016 de Colpensiones (que neg\u00f3 el reconocimiento de la pensi\u00f3n de invalidez al \u00a0 tutelante), el se\u00f1or Lizardo Narv\u00e1ez Valencia cotiz\u00f3 3.516 d\u00edas entre el 10 de \u00a0 marzo de 1974 y el 15 de abril de 1989. Por tanto, cotiz\u00f3, como m\u00ednimo 502 \u00a0 semanas antes de la entrada en vigencia del Sistema General de Seguridad Social \u00a0 en Pensiones de la Ley 100 de 1993. As\u00ed las cosas, el tutelante contaba con m\u00e1s \u00a0 de 300 semanas antes de la entrada en vigencia de la Ley 100 de 1993. En \u00a0 consecuencia, cumpli\u00f3 con el requisito previsto por el Acuerdo 049 de 1990 \u00a0 (Decreto 758 de 1990). \u00a0 \u00a0<\/p>\n<p>68. En ese orden de ideas, teniendo en cuenta las reglas de unificaci\u00f3n, la \u00a0 situaci\u00f3n especial del accionante y su particular estado de vulnerabilidad, esta \u00a0 Sala de Revisi\u00f3n concluye que corresponde aplicar al presente caso el precedente \u00a0 vinculante contenido en la sentencia SU-442 de 2016. As\u00ed, entonces, se conceder\u00e1 \u00a0 el amparo solicitado por el se\u00f1or Lizardo Narv\u00e1ez Valencia, de manera definitiva \u00a0 y, por ende, se ordenar\u00e1 a Colpensiones el reconocimiento de la pensi\u00f3n de \u00a0 invalidez conforme a los requisitos del Acuerdo 049 de 1990 y con sujeci\u00f3n a las \u00a0 reglas jurisprudenciales fijadas por la Sentencia SU-442 de 2016 y la parte \u00a0 considerativa de esta providencia. \u00a0 \u00a0<\/p>\n<p>4. S\u00edntesis \u00a0 \u00a0<\/p>\n<p>69. La Sala de Revisi\u00f3n consider\u00f3 procedente, de manera definitiva, la acci\u00f3n de \u00a0 tutela, por satisfacer los requisitos de legitimaci\u00f3n en la causa, \u00a0 subsidiariedad e inmediatez. En relaci\u00f3n con el supuesto de subsidiariedad, \u00a0 consider\u00f3 que la acci\u00f3n de tutela era procedente de manera definitiva, debido a \u00a0 la especial situaci\u00f3n de riesgo en la que se encuentra el tutelante. Para \u00a0 efectos de resolver el problema jur\u00eddico sustancial, realiz\u00f3 un ejercicio de \u00a0 subsunci\u00f3n de las condiciones f\u00e1cticas y normativas del caso en las reglas de \u00a0 unificaci\u00f3n de la Sentencia SU-442 de 2016, relativas al principio de la \u00a0 condici\u00f3n m\u00e1s beneficiosa en materia de pensi\u00f3n de invalidez. Con fundamento en \u00a0 este, orden\u00f3 a Colpensiones el reconocimiento y pago de la pensi\u00f3n de invalidez \u00a0 al accionante, dado que se trataba de una persona vulnerable y al acreditarse, \u00a0 en su caso, las exigencias dispuestas en el Acuerdo 049 de 1990 para dicho \u00a0 reconocimiento. \u00a0 \u00a0<\/p>\n<p>70. \u00a0Por \u00a0 \u00faltimo, esta Sala no puede soslayar el hecho de que la \u00a0 abogada Gloria Yobana Castro Torres pese a tener su tarjeta profesional \u00a0 suspendida durante el periodo comprendido entre el 31 de mayo y el 31 de agosto \u00a0 de 2018, continu\u00f3 su ejercicio profesional con la presentaci\u00f3n de la acci\u00f3n de \u00a0 tutela en representaci\u00f3n del se\u00f1or Narv\u00e1ez, raz\u00f3n por la cual, se compulsar\u00e1 \u00a0 copias a la Sala Jurisdiccional Disciplinaria del Consejo Seccional de la \u00a0 Judicatura de Risaralda para que se determine lo que corresponda, en relaci\u00f3n \u00a0 con la conducta de la mencionada abogada. \u00a0 \u00a0<\/p>\n<p>III. DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>71. En m\u00e9rito de lo expuesto, la Sala Primera de Revisi\u00f3n de Tutelas de la Corte \u00a0 Constitucional, en nombre del pueblo y por mandato de la Constituci\u00f3n, \u00a0 \u00a0<\/p>\n<p>RESUELVE \u00a0 \u00a0<\/p>\n<p>PRIMERO.- REVOCAR\u00a0la \u00a0 sentencia dictada por el Juzgado Primero Civil del Circuito Especializado en \u00a0 Restituci\u00f3n de Tierras de Pereira y, en su lugar, CONCEDER, de manera \u00a0 definitiva, el amparo de los derechos fundamentales a la seguridad social, vida \u00a0 digna y m\u00ednimo vital del se\u00f1or Lizardo Narv\u00e1ez Valencia, de conformidad con las \u00a0 consideraciones contenidas en la sentencia SU-442 de 2016 y la parte \u00a0 considerativa de esta providencia. \u00a0 \u00a0<\/p>\n<p>SEGUNDO.- ORDENAR a Colpensiones que \u00a0 dentro de las 48 horas siguientes a la notificaci\u00f3n del presente fallo reconozca \u00a0 la pensi\u00f3n de invalidez al se\u00f1or Lizardo Narv\u00e1ez Valencia y, en consecuencia, \u00a0 realice el pago de las mesadas pensionales al se\u00f1or Lizardo Narv\u00e1ez Valencia, \u00a0 teniendo en cuenta las reglas jurisprudenciales fijadas por la Sentencia SU-442 \u00a0 de 2016 y de conformidad con lo expuesto en la parte considerativa de esta \u00a0 providencia. \u00a0 \u00a0<\/p>\n<p>TERCERO.- COMPULSAR COPIAS\u00a0del expediente\u00a0y de \u00a0 esta sentencia, a la Sala Jurisdiccional Disciplinaria del Consejo Superior de \u00a0 la Judicatura, para\u00a0que investigue la conducta de abogada Gloria Yobana Castro \u00a0 Torres. Para el efecto, la \u00a0 Secretar\u00eda General de la Corte Constitucional realizar\u00e1 los desgloses y \u00a0 anotaciones respectivas. \u00a0 \u00a0<\/p>\n<p>CUARTO.- Por Secretar\u00eda \u00a0 General,\u00a0EXPEDIR\u00a0las comunicaciones de que trata el art\u00edculo 36 del \u00a0 Decreto 2591 de 1991, para los efectos all\u00ed contemplados. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>Comun\u00edquese y \u00a0 c\u00famplase, \u00a0 \u00a0<\/p>\n<p>CARLOS BERNAL PULIDO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>DIANA FAJARDO RIVERA \u00a0 \u00a0<\/p>\n<p>Magistrada \u00a0 \u00a0<\/p>\n<p>LUIS GUILLERMO GUERRERO P\u00c9REZ \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>MARTHA S\u00c1CHICA M\u00c9NDEZ \u00a0 \u00a0<\/p>\n<p>Secretaria General \u00a0 \u00a0<\/p>\n<p>[1] Mediante auto de 9 de noviembre, \u00a0 esta Sala decret\u00f3 la desacumulaci\u00f3n procesal de los expedientes T-6.964.270 y \u00a0 T-6.958.286, para que fueran fallados de manera independiente. \u00a0 \u00a0<\/p>\n<p>[2] Folios 14-14 vto.,\u00a0 17-18. \u00a0 Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[3] Folio 14. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[4] Folios 14-15. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[5] Folios 17-20. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[6] Folios 21-50. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[7] Folio 7. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[8] Folio 5. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[10] Folios 72-82. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[11] Folios 83-87. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[12] Folio 10. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[13] \u00a0Corte Constitucional. Sentencia T-550 de 1993. \u00a0 \u00a0<\/p>\n<p>[14] \u00a0Corte Constitucional. Sentencia T-459 de 1992. \u00a0 \u00a0<\/p>\n<p>[15] \u00a0Ib\u00eddem. \u00a0 \u00a0<\/p>\n<p>[16] Corte Constitucional. Sentencia T-314 de 1995. \u00a0 \u00a0<\/p>\n<p>[17] \u00a0 Art\u00edculo 10, inciso final. \u00a0 \u00a0<\/p>\n<p>[18] \u00a0Ib\u00eddem. \u00a0 \u00a0<\/p>\n<p>[19] \u00a0Estatuto del Abogado. Se advierte que el art\u00edculo 112 de la Ley 1123 de 2007 \u00a0 derog\u00f3 las normas del Decreto 196 de 1971 que le fueran contrarias, no obstante \u00a0 la mencionada disposici\u00f3n a\u00fan se encuentra vigente por no ser incompatible con \u00a0 las normas contenidas en la referida normativa. \u00a0 \u00a0<\/p>\n<p>[20] Art\u00edculo 29 de la Ley 1123 de 2007: \u00a0 INCOMPATIBILIDADES. \u201cNo pueden ejercer la abogac\u00eda, aunque se hallen \u00a0 inscritos: (\u2026). 4. Los abogados suspendidos o excluidos de la profesi\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>[21]Corte Constitucional. Sentencia \u00a0 T-531 de 2002. \u00a0 \u00a0<\/p>\n<p>[22] Ib\u00eddem. \u00a0 \u00a0<\/p>\n<p>[23] \u00a0Folio 12. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[24] \u00a0 http:\/\/antecedentesdisciplinarios.ramajudicial.gov.co\/Default.aspx \u00a0 \u00a0<\/p>\n<p>[25] Art\u00edculo 46: \u201cEl Estado, la \u00a0 sociedad y la familia concurrir\u00e1n para la protecci\u00f3n y la asistencia de las \u00a0 personas de la tercera edad y promover\u00e1n su integraci\u00f3n a la vida activa y \u00a0 comunitaria. \/\/ El Estado les garantizar\u00e1 los servicios de la seguridad social \u00a0 integral y el subsidio alimentario en caso de indigencia\u201d. \u00a0 \u00a0<\/p>\n<p>[26] Art\u00edculo 7: Para fines de la \u00a0 presente ley, se adoptan las siguientes definiciones: \u201c(\u2026).b) Adulto Mayor. Es \u00a0 aquella persona que cuenta con sesenta (60) a\u00f1os de edad o m\u00e1s. A criterio de \u00a0 los especialistas de los centros vida, una persona podr\u00e1 ser clasificada dentro \u00a0 de este rango, siendo menor de 60 a\u00f1os y mayor de 55, cuando sus condiciones de \u00a0 desgaste f\u00edsico, vital y psicol\u00f3gico as\u00ed lo determinen; (\u2026)\u201d. \u00a0 \u00a0<\/p>\n<p>[27] Consultar, entre otras, las \u00a0 sentencias T-047 de 2015 y T-339 de 2017 de la Corte Constitucional. \u00a0 \u00a0<\/p>\n<p>[28] Folios 67 vto.-68. Cuaderno \u00a0 principal. \u00a0 \u00a0<\/p>\n<p>[29] Folio 57. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[30] Folio 4. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[31] \u00a0https:\/\/wssisbenconsulta.sisben.gov.co\/dnp_sisbenconsulta\/dnp_sisben_consulta.aspx \u00a0 \u00a0<\/p>\n<p>[32] Folio 4. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[33] Corte \u00a0 Constitucional. Sentencia C-1194 de 2008. \u00a0La jurisprudencia constitucional ha definido el principio de \u00a0 buena fe como aquel que exige a los particulares y a las autoridades p\u00fablicas \u00a0 ajustar sus comportamientos a una conducta honesta, leal y conforme con las \u00a0 actuaciones que podr\u00edan esperarse de una \u201cpersona correcta (vir bonus)\u201d. As\u00ed \u00a0 la buena fe presupone la existencia de relaciones reciprocas con trascendencia \u00a0 jur\u00eddica, y se refiere a la \u201cconfianza, seguridad y credibilidad que otorga la \u00a0 palabra dada\u201d (Se destaca). \u00a0 \u00a0<\/p>\n<p>[34] \u00a0 Corte Constitucional. Sentencia T-162 de 1997.\u00a0 \u00a0 Uno de los principios m\u00e1s importantes que rige el tr\u00e1mite de la acci\u00f3n de tutela \u00a0 es el de la informalidad. Este rasgo surge de la naturaleza y finalidad \u00a0 misma de la acci\u00f3n, pues al ser la tutela el medio que confiri\u00f3 la Constituci\u00f3n \u00a0 Pol\u00edtica a los ciudadanos para hacer efectivos sus derechos fundamentales, es \u00a0 necesario excluir el ritualismo y el tecnicismo. De hecho, al ser una acci\u00f3n que \u00a0 pueden interponer las personas sin mayores conocimientos jur\u00eddicos, es imposible \u00a0 exigir en su tr\u00e1mite formalidades que entienden y manejan s\u00f3lo los expertos en \u00a0 derecho. Por otro lado, la protecci\u00f3n que reclaman con tanta urgencia los \u00a0 derechos fundamentales, y que la tutela pretende brindar, no se puede supeditar \u00a0 a la observancia de cuestiones meramente procesales\u201d \u00a0 \u00a0<\/p>\n<p>[35] Con relaci\u00f3n a este \u00a0 requisito de procedencia, el art\u00edculo 10 del Decreto-ley 2591 de 1991 dispone: \u00a0 \u201cArt\u00edculo 10. Legitimidad e inter\u00e9s. La acci\u00f3n de tutela podr\u00e1 ser ejercida, en \u00a0 todo momento y lugar, por cualquiera persona vulnerada o amenazada en uno de sus \u00a0 derechos fundamentales, quien actuar\u00e1 por s\u00ed misma o a trav\u00e9s de representante. \u00a0 Los poderes se presumir\u00e1n aut\u00e9nticos. || Tambi\u00e9n se pueden agenciar derechos \u00a0 ajenos cuando el titular de los mismos no est\u00e9 en condiciones de promover su \u00a0 propia defensa. Cuando tal circunstancia ocurra, deber\u00e1 manifestarse en la \u00a0 solicitud\u201d. \u00a0 \u00a0<\/p>\n<p>[36] \u00a0 Folio 14. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[37] \u00a0 Folio 14. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[38] \u00a0Folio 14. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[39] \u00a0Folio 14. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[40] \u00a0Folios 14-15. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[41] \u00a0Folio 17. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[42] \u00a0Folios 17-20. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[43] En los t\u00e9rminos de los art\u00edculos 46 superior[43], \u00a0 7 de la Ley 1276 de 2009. \u00a0 \u00a0<\/p>\n<p>[44] Folio 5. Cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[45] Corte Constitucional. Sentencia \u00a0 SU-442 de 2016.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-024-19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 Sentencia T-024\/19 \u00a0 \u00a0 ACCION DE TUTELA PARA RECONOCIMIENTO DE PENSION DE INVALIDEZ-Procedencia excepcional \u00a0 \u00a0 LEGITIMACION POR ACTIVA EN TUTELA-Formas previstas por \u00a0 ordenamiento jur\u00eddico \u00a0 \u00a0 ACTO DE APODERAMIENTO-Concepto\/APODERADO JUDICIAL EN \u00a0 TUTELA-Requisitos \u00a0 \u00a0 Esta Corporaci\u00f3n ha precisado que i) \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126],"tags":[],"class_list":["post-26624","post","type-post","status-publish","format-standard","hentry","category-tutelas-2019"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/26624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=26624"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/26624\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=26624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=26624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=26624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}