{"id":26656,"date":"2024-07-02T17:18:03","date_gmt":"2024-07-02T17:18:03","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/07\/02\/t-076-19\/"},"modified":"2024-07-02T17:18:03","modified_gmt":"2024-07-02T17:18:03","slug":"t-076-19","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-076-19\/","title":{"rendered":"T-076-19"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-076-19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia T-076\/19 \u00a0 \u00a0<\/p>\n<p>DERECHO A LA CALIFICACION DE LA PERDIDA DE LA CAPACIDAD LABORAL DE MENOR, QUIEN \u00a0 SUFRIO ACCIDENTE DE TRANSITO \u00a0 \u00a0<\/p>\n<p>CALIFICACION DE LA PERDIDA DE LA CAPACIDAD LABORAL-Determinaci\u00f3n de \u00a0 la competencia en los eventos de accidentes de tr\u00e1nsito y eventos catastr\u00f3ficos \u00a0 \u00a0<\/p>\n<p>CARENCIA ACTUAL DE OBJETO POR HECHO SUPERADO-Aseguradora \u00a0 sufrag\u00f3 los honorarios de la Junta Regional de Calificaci\u00f3n de Invalidez \u00a0 \u00a0<\/p>\n<p>Referencia: Expediente T-7.013.230 \u00a0 \u00a0<\/p>\n<p>Acci\u00f3n de tutela presentada por Martha Isabel Bele\u00f1o Hurtado, en representaci\u00f3n \u00a0 de Luis Daniel Camacho Bele\u00f1o, contra Seguros del Estado S.A. \u00a0 \u00a0<\/p>\n<p>Magistrado ponente: \u00a0 \u00a0<\/p>\n<p>CARLOS \u00a0 BERNAL PULIDO \u00a0 \u00a0<\/p>\n<p>Bogot\u00e1 D.C., veintis\u00e9is (26) de febrero de dos mil diecinueve (2019) \u00a0 \u00a0<\/p>\n<p>La Sala Primera de Revisi\u00f3n de la Corte Constitucional, integrada por la \u00a0 Magistrada Diana Fajardo Rivera y por los Magistrados Luis Guillermo Guerrero \u00a0 P\u00e9rez y Carlos Bernal Pulido, quien la preside, en ejercicio de sus competencias \u00a0 constitucionales y legales, ha proferido la siguiente \u00a0 \u00a0<\/p>\n<p>SENTENCIA \u00a0 \u00a0<\/p>\n<p>En el tr\u00e1mite de revisi\u00f3n del fallo de \u00a0 segunda instancia proferido por el Juzgado Primero Penal del Circuito con \u00a0 funciones de conocimiento de Cartagena, el 2 de agosto de 2018, que revoc\u00f3 la \u00a0 sentencia dictada por el Juzgado Noveno Penal Municipal de Cartagena, el 20 de \u00a0 junio del a\u00f1o en cita, en el marco de la acci\u00f3n de tutela instaurada por la \u00a0 se\u00f1ora Martha Isabel Bele\u00f1o Hurtado contra Seguros del Estado S.A. \u00a0 \u00a0<\/p>\n<p>Conforme a lo dispuesto en los art\u00edculos 86 de la Constituci\u00f3n Pol\u00edtica y 33 del \u00a0 Decreto-ley 2591 de 1991, la Sala de Selecci\u00f3n n\u00famero 10 de la Corte \u00a0 Constitucional escogi\u00f3 para efectos de revisi\u00f3n el asunto de la referencia[1]. \u00a0 \u00a0<\/p>\n<p>I.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0ANTECEDENTES \u00a0 \u00a0<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0El 16 de mayo de 2018, la ciudadana Martha Isabel Bele\u00f1o Hurtado present\u00f3, en \u00a0 nombre de su hijo Luis Daniel Camacho Bele\u00f1o, acci\u00f3n de tutela en contra de \u00a0 Seguros del Estado S.A., a fin de que se protegieran los derechos fundamentales \u00a0 a la salud y debido proceso de su hijo Luis Daniel, los que estim\u00f3 vulnerados \u00a0 con ocasi\u00f3n de la negativa de Seguros del Estado S.A. de valorar la p\u00e9rdida de \u00a0 capacidad laboral del menor. \u00a0 \u00a0<\/p>\n<p>1.\u00a0 Hechos \u00a0 probados \u00a0 \u00a0<\/p>\n<p>2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0El 18 de enero de 2017, Luis Daniel Camacho Bele\u00f1o, quien tiene 11 a\u00f1os[2], sufri\u00f3 \u00a0 un accidente de tr\u00e1nsito que le produjo una \u201cfractura de clav\u00edcula\u201d \u00a0y \u201ctraumatismo en diferentes partes del cuerpo\u201d[3]. \u00a0 \u00a0<\/p>\n<p>3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0La motocicleta que caus\u00f3 el siniestro se encontraba amparada por la p\u00f3liza de \u00a0 seguro obligatorio de accidentes de tr\u00e1nsito -SOAT- AT 1329-34086205-6, expedida \u00a0 por Seguros del Estado S.A.[4] \u00a0 \u00a0<\/p>\n<p>4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0El 20 de marzo de 2018, la ciudadana Martha Isabel Bele\u00f1o Hurtado solicit\u00f3 a \u00a0 Seguros del Estado S.A. que valorara o hiciera valorar a Luis Daniel Camacho \u00a0 Bele\u00f1o, a fin de que determinara la p\u00e9rdida de capacidad laboral del menor[5]. La \u00a0 valoraci\u00f3n resultaba indispensable para solicitar el pago de la indemnizaci\u00f3n \u00a0 por incapacidad permanente ocasionada por el mencionado accidente de tr\u00e1nsito. \u00a0 \u00a0<\/p>\n<p>5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Mediante comunicaci\u00f3n DJ-6265\/18 de 11 de abril de 2018, la compa\u00f1\u00eda aseguradora \u00a0 neg\u00f3 la solicitud presentada por la tutelante. Indic\u00f3 que \u201cle corresponde a \u00a0 la se\u00f1ora Martha Isabel Bele\u00f1o Hurtado, en calidad de representante legal del \u00a0 menor Luis Daniel Camacho Bele\u00f1o, obtener a trav\u00e9s de la EPS o EPSS, su \u00a0 valoraci\u00f3n y con ello formalizar ante la Aseguradora la reclamaci\u00f3n por \u00a0 Incapacidad Permanente\u201d[6]. \u00a0 \u00a0<\/p>\n<p>6.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0La accionante adujo que Seguros del Estado S.A. se encontraba obligada a \u00a0 efectuar la valoraci\u00f3n m\u00e9dica para establecer las secuelas generadas por el \u00a0 accidente de tr\u00e1nsito sufrido por su hijo Luis Daniel. \u00a0 \u00a0<\/p>\n<p>7.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0Por \u00faltimo, sostuvo que \u201ces ama de casa (sic) del cual no cuenta con un \u00a0 salario fijo mensual, tiene un hijo de 17 a\u00f1os es estudiante (sic), vive en casa \u00a0 familiar (sic) del cual tiene obligaciones tales como estudio, transporte, \u00a0 alimentaci\u00f3n y servicios\u201d[7]. \u00a0 \u00a0<\/p>\n<p>2.\u00a0\u00a0\u00a0\u00a0 \u00a0Solicitud de tutela \u00a0 \u00a0<\/p>\n<p>8.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0La se\u00f1ora Martha Isabel Bele\u00f1o Hurtado solicit\u00f3 al juez de tutela que amparara \u00a0 los derechos fundamentales a la salud y debido proceso de su hijo, que consider\u00f3 \u00a0 amenazados, con ocasi\u00f3n de la negativa de Seguros del Estado S.A. de realizarle \u00a0 la valoraci\u00f3n m\u00e9dica en \u201cprimera instancia\u201d[8]. \u00a0Por tal raz\u00f3n, le pidi\u00f3 al juez constitucional que ordenara a dicha compa\u00f1\u00eda \u00a0 aseguradora \u201csufragar directamente los honorarios a favor de la Junta \u00a0 Regional de Calificaci\u00f3n de Invalidez de Bol\u00edvar\u201d[9], \u00a0para que esta entidad emita el dictamen de p\u00e9rdida de capacidad laboral del \u00a0 menor. \u00a0 \u00a0<\/p>\n<p>3.\u00a0\u00a0\u00a0\u00a0 \u00a0Respuesta de la sociedad accionada \u00a0 \u00a0<\/p>\n<p>9.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El 17 de mayo de \u00a0 2018, el Juez Noveno Penal Municipal de Cartagena admiti\u00f3 la tutela y ofici\u00f3 a \u00a0 la accionada Seguros del Estado S.A. para que ejerciera su derecho de defensa[10]. \u00a0 \u00a0<\/p>\n<p>10.\u00a0 El 6 de junio de \u00a0 2018, el apoderado general de Seguros del Estado S.A. solicit\u00f3 declarar la \u00a0 improcedencia de la presente acci\u00f3n de tutela. Afirm\u00f3 que dicha sociedad no \u00a0 hab\u00eda vulnerado los derechos del menor Luis Daniel Camacho Bele\u00f1o, habida cuenta \u00a0 de que \u201cno tiene el deber legal de asumir la valoraci\u00f3n y el costo de los \u00a0 honorarios de las Juntas de Calificaci\u00f3n de Invalidez, pues este costo no se \u00a0 encuentra establecido dentro de los amparos del Seguro Obligatorio de Accidentes \u00a0 de Tr\u00e1nsito SOAT, se\u00f1alados por las diferentes disposiciones legales\u201d[11]. \u00a0 \u00a0<\/p>\n<p>11.\u00a0 As\u00ed mismo, pidi\u00f3 \u00a0 al juez de tutela, en caso de acceder a la pretensi\u00f3n de amparo, \u201cpermitir a \u00a0 la compa\u00f1\u00eda se afecte el amparo de la Incapacidad Permanente y descuente de la \u00a0 suma indemnizatoria que resultare a pagar, el costo de la valoraci\u00f3n por parte \u00a0 de la Junta Regional de Calificaci\u00f3n de Invalidez competente\u201d[12]. \u00a0 \u00a0<\/p>\n<p>4.\u00a0\u00a0\u00a0\u00a0 Decisiones objeto de revisi\u00f3n \u00a0 \u00a0<\/p>\n<p>4.1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Primera instancia[13] \u00a0 \u00a0<\/p>\n<p>12.\u00a0 \u00a0 \u00a0El 20 de junio de 2018[14], \u00a0 el Juzgado Noveno Penal Municipal de Cartagena ampar\u00f3 los derechos fundamentales \u00a0 a la salud y debido proceso de Luis Daniel Camacho Bele\u00f1o. \u00a0 \u00a0<\/p>\n<p>13.\u00a0 \u00a0 \u00a0Sostuvo que \u201cno le asiste raz\u00f3n a la aseguradora demandada cuando afirma que \u00a0 el pago de los honorarios de la Junta Regional de Calificaci\u00f3n de Invalidez, no \u00a0 radica dentro de sus obligaciones, pues de conformidad con lo establecido en la \u00a0 ley y el art. 50 del Decreto 2463 de 2001 y lo expuesto por la Jurisprudencia, \u00a0 \u00e9sta s\u00ed es una obligaci\u00f3n de aquella, y m\u00e1s cuando el dictamen de calificaci\u00f3n \u00a0 de p\u00e9rdida de capacidad laboral, al tiempo es requisito indispensable exigido \u00a0 por la ley y por las mismas aseguradoras para proceder con el reconocimiento \u00a0 econ\u00f3mico de la indemnizaci\u00f3n permanente\u201d[15]. \u00a0 \u00a0<\/p>\n<p>14.\u00a0 \u00a0 \u00a0En consecuencia, orden\u00f3 a Seguros del Estado S.A. que procediera a pagar a la \u00a0 correspondiente Junta Regional de Calificaci\u00f3n de Invalidez, los honorarios \u00a0 profesionales requeridos para la pr\u00e1ctica del dictamen de p\u00e9rdida de capacidad \u00a0 laboral del menor, como requisito para acceder al amparo de indemnizaci\u00f3n por \u00a0 incapacidad permanente. \u00a0 \u00a0<\/p>\n<p>4.2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Impugnaci\u00f3n[16] \u00a0 \u00a0<\/p>\n<p>15.\u00a0 \u00a0 \u00a0El 27 de junio de 2018, Seguros del Estado S.A. impugn\u00f3 la sentencia de primera \u00a0 instancia. A su juicio, \u201cla acci\u00f3n de tutela que busca resolver controversias \u00a0 frente a un dictamen de p\u00e9rdida de capacidad laboral, inicialmente, resulta \u00a0 improcedente\u201d, m\u00e1xime teniendo en cuenta que ni la salud ni mucho menos la \u00a0 vida del menor Luis Daniel se encuentran en riesgo[17]. \u00a0 \u00a0<\/p>\n<p>16.\u00a0 \u00a0 \u00a0Por otra parte, se\u00f1al\u00f3 que el a quo hab\u00eda desconocido lo dispuesto en el \u00a0 art\u00edculo 142 del Decreto 019 de 2012[18], \u00a0 seg\u00fan el cual, las compa\u00f1\u00edas de seguros que administran recursos del seguro \u00a0 obligatorio para v\u00edctimas de accidentes de tr\u00e1nsito -SOAT- no se encuentran \u00a0 obligadas a calificar la p\u00e9rdida de capacidad laboral. En el mismo sentido, \u00a0 manifest\u00f3 que de conformidad con los Decretos 056 de 2015 y 780 de 2016, el pago \u00a0 de honorarios de la Junta Regional de Calificaci\u00f3n de Invalidez no es una \u00a0 obligaci\u00f3n contractual, ni legal, de Seguros del Estado S.A. \u00a0 \u00a0<\/p>\n<p>17.\u00a0 \u00a0 \u00a0Finalmente, afirm\u00f3 que la seguridad social no es un derecho fundamental, sino \u00a0 econ\u00f3mico, prestacional y program\u00e1tico. As\u00ed pues, sostuvo que en el caso \u00a0 concreto no se estaba ante una situaci\u00f3n de peligro para la vida, integridad \u00a0 personal, o de otros derechos fundamentales, en forma directa ni por conexidad, \u00a0 pues lo pretendido era el pago del examen de la Junta Regional de Calificaci\u00f3n \u00a0 de Invalidez. Por ende, consider\u00f3 que no se estaba en presencia de una situaci\u00f3n \u00a0 que habilitara la intervenci\u00f3n del juez constitucional. \u00a0 \u00a0<\/p>\n<p>4.3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Segunda Instancia[19] \u00a0 \u00a0<\/p>\n<p>18.\u00a0 \u00a0 \u00a0\u00a0El 2 de agosto de 2018, el Juzgado Primero Penal del Circuito con funciones de \u00a0 conocimiento de Cartagena revoc\u00f3 la decisi\u00f3n de primera instancia, al considerar \u00a0 que \u201cla carga con respecto al pago de honorarios de las Juntas de \u00a0 Calificaci\u00f3n de Invalidez, le corresponde al solicitante, por lo que en el \u00a0 presente evento, le ata\u00f1e a la se\u00f1ora Martha Isabel Bele\u00f1o Hurtado en \u00a0 representaci\u00f3n del menor Luis Daniel Camacho Bele\u00f1o; eso s\u00ed, otorg\u00e1ndole la \u00a0 opci\u00f3n de solicitar el reembolso del mismo ante la Administradora de Riesgos \u00a0 Laborales o Administradora del Sistema General de Pensiones, seg\u00fan sea el caso, \u00a0 siempre que el dictamen determine una p\u00e9rdida de capacidad laboral superior a un \u00a0 50%\u201d[20]. \u00a0 \u00a0<\/p>\n<p>19.\u00a0 \u00a0 \u00a0Agreg\u00f3 que el art\u00edculo 20 del Decreto 132 de 2017 \u201cno contempla obligaci\u00f3n \u00a0 alguna dirigida a las compa\u00f1\u00edas aseguradoras autorizadas para expedir el SOAT, \u00a0 donde tengan que sufragar con el costo de los honorarios de la Junta Regional de \u00a0 Invalidez, ni siquiera rembolsar el monto cancelado por el solicitante afectado \u00a0 si se llegare a cumplir el requisito establecido\u201d[21]. \u00a0 \u00a0<\/p>\n<p>5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Actuaciones adelantadas en sede de revisi\u00f3n \u00a0 \u00a0<\/p>\n<p>5.1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Pruebas decretadas en sede de revisi\u00f3n \u00a0 \u00a0<\/p>\n<p>20.\u00a0 Mediante auto del \u00a0 30 de noviembre de 2018[22] \u00a0se \u00a0 requiri\u00f3 a la se\u00f1ora Martha Isabel Bele\u00f1o Hurtado para que informara acerca de \u00a0 la conformaci\u00f3n de su n\u00facleo familiar y de su situaci\u00f3n econ\u00f3mica. As\u00ed mismo, \u00a0 que informara si su hijo Luis Daniel cuenta con alg\u00fan servicio m\u00e9dico, y cu\u00e1les \u00a0 han sido las actuaciones adelantadas ante la EPS, Junta Regional de Calificaci\u00f3n \u00a0 de Invalidez u otra entidad del Sistema de Seguridad Social para obtener la \u00a0 calificaci\u00f3n de p\u00e9rdida de capacidad laboral del menor. \u00a0 \u00a0<\/p>\n<p>21.\u00a0 \u00a0 \u00a0A su vez, se pidi\u00f3 a la Junta Regional de Calificaci\u00f3n de Invalidez de Bol\u00edvar \u00a0 que informara sobre la competencia para calificar la p\u00e9rdida de capacidad \u00a0 laboral de quien pretende ser beneficiario del amparo por incapacidad \u00a0 permanente, en virtud de la p\u00f3liza de seguro obligatorio de da\u00f1os corporales \u00a0 causado a personas en accidentes de tr\u00e1nsito -SOAT-. As\u00ed mismo, que indicara si \u00a0 el dictamen expedido por esta autoridad es la \u00fanica prueba conducente para \u00a0 reclamar el amparo pretendido por el accionante, o por el contrario, es posible \u00a0 presentar otro elemento probatorio. \u00a0 \u00a0<\/p>\n<p>Tambi\u00e9n, se le requiri\u00f3 para que manifestara: (i) el monto a pagar \u00a0 por concepto del dictamen de calificaci\u00f3n de p\u00e9rdida de capacidad laboral, \u00a0 (ii) \u00a0si el solicitante puede pedir el amparo de pobreza, (iii) quien \u00a0 puede sufragar el valor de dicho examen, y, (iv) si la Junta puede \u00a0 practicarlo con posibilidad de recobro a las compa\u00f1\u00edas aseguradoras de SOAT. \u00a0 \u00a0<\/p>\n<p>Finalmente, se solicit\u00f3 que indicara si ha recibido solicitud de calificaci\u00f3n \u00a0 por parte del menor Luis Daniel Camacho Bele\u00f1o, y de ser as\u00ed, el tr\u00e1mite en que \u00a0 se encuentra. \u00a0 \u00a0<\/p>\n<p>22.\u00a0 \u00a0 \u00a0Por otra parte, se ofici\u00f3 a la Asociaci\u00f3n Mutual Ser Empresa Solidaria de Salud \u00a0 E.S.S. a fin de que explicara si en su calidad de EPS-S es competente para \u00a0 dictaminar la p\u00e9rdida de capacidad laboral de un afiliado, y en caso afirmativo, \u00a0 si este documento es prueba pertinente y conducente para reclamar el amparo por \u00a0 incapacidad permanente cubierto por el SOAT. Por otra parte, se pidi\u00f3 que \u00a0 indicara el costo y tr\u00e1mite para la solicitud del certificado m\u00e9dico de \u00a0 valoraci\u00f3n p\u00e9rdida de capacidad laboral en primera oportunidad, y en ese \u00a0 sentido, que manifestara si ha recibido solicitud de evaluaci\u00f3n por parte de \u00a0 Luis Daniel Camacho Bele\u00f1o. \u00a0 \u00a0<\/p>\n<p>23.\u00a0 \u00a0 \u00a0Finalmente, se requiri\u00f3 a Seguros del Estado S.A. para que se\u00f1alara si el \u00a0 dictamen de p\u00e9rdida de capacidad laboral expedido por la Junta Regional de \u00a0 Calificaci\u00f3n de Invalidez es la \u00fanica prueba conducente para reclamar el pago de \u00a0 indemnizaci\u00f3n por incapacidad permanente ocasionada por un accidente de \u00a0 tr\u00e1nsito, o si, \u00a0 por el contrario, es posible que el solicitante del amparo presente otro examen \u00a0 o certificado m\u00e9dico. Se le solicit\u00f3 tambi\u00e9n que indicara si ha realizado la \u00a0 calificaci\u00f3n de p\u00e9rdida de capacidad laboral a otros solicitantes de las \u00a0 prestaciones cubiertas por el SOAT durante el \u00faltimo a\u00f1o, indicando el motivo de \u00a0 la pr\u00e1ctica de la valoraci\u00f3n. Por \u00faltimo, se le pidi\u00f3 remitir copia de las \u00a0 gestiones y tr\u00e1mites relacionados con la solicitud de calificaci\u00f3n de p\u00e9rdida de \u00a0 capacidad laboral y asunci\u00f3n de pago de honorarios de la Junta Regional de \u00a0 Calificaci\u00f3n de Invalidez, elevada por la se\u00f1ora Martha Isabel Bele\u00f1o Hurtado en \u00a0 calidad de representante legal de Luis Daniel Camacho Bele\u00f1o. \u00a0 \u00a0<\/p>\n<p>5.2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Pruebas aportadas en sede de revisi\u00f3n \u00a0 \u00a0<\/p>\n<p>24.\u00a0 El 11 de \u00a0 diciembre de 2018, la se\u00f1ora Martha Isabel Bele\u00f1o Hurtado, mediante comunicaci\u00f3n \u00a0 allegada por correo electr\u00f3nico, dio respuesta a la informaci\u00f3n requerida por el \u00a0 magistrado sustanciador en el numeral primero del auto de pruebas[23]. \u00a0 En efecto, la ciudadana manifest\u00f3 que: \u00a0 \u00a0<\/p>\n<p>\u201c1. Tengo tres personas a cargo, quienes son mis hijos y mi se\u00f1ora madre; 2. Mi \u00a0 n\u00facleo familiar se encuentra integrado por mi madre quien es ama de casa y mis \u00a0 dos menores hijos quienes son estudiantes; 3. No alcanzo a suplir todas mis \u00a0 necesidades econ\u00f3micas, toda vez que laboro por d\u00edas en oficios varios en casas \u00a0 de familia; 4. El padre de Luis Daniel Camacho gira cada ocho d\u00edas 30 mil pesos; \u00a0 5. No tengo profesi\u00f3n por lo que l\u00e1baro (sic) por \u00a0 turnos en oficios varios, el turno me lo pagan a 30 mil pesos y mensualmente en \u00a0 promedio me hago unos 500 mil pesos, por tanto es un poco precaria mi situaci\u00f3n \u00a0 econ\u00f3mica; 6. No cuento con ninguna propiedad ni ning\u00fan tipo de veh\u00edculo; 7. En \u00a0 alimentaci\u00f3n me gasto en promedio unos 250 mil pesos, en vestuario no puedo \u00a0 tener gastos, en recreaci\u00f3n 50 mil pesos, 150 en arriendo en casa familiar, 50 \u00a0 mil en servicios p\u00fablicos; 8. Luis Daniel pertenece al r\u00e9gimen subsidiado con \u00a0 Mutual Ser; 9. No present\u00e9 ninguna solicitud de valoraci\u00f3n ante la EPS, toda vez \u00a0 que el abogado que me asesor\u00f3 me manifest\u00f3 que las normas indicaban que por ser \u00a0 un accidente de tr\u00e1nsito quien deb\u00eda valorarlo en primera oportunidad era la \u00a0 compa\u00f1\u00eda aseguradora; 10. Mi hijo Luis Daniel ya fue valorado ante la \u00a0 Junta Regional de Calificaci\u00f3n de Invalidez de Bol\u00edvar y se encuentra esperando \u00a0 los resultados, toda vez que la aseguradora cancel\u00f3 los honorarios por orden de \u00a0 un fallo de tutela; 11. No se present\u00f3 dicha certificaci\u00f3n a la \u00a0 aseguradora, toda vez que ellos se negaron rotundamente a valorar a mi hijo \u00a0 manifestando que no les correspond\u00eda\u201d[24] \u00a0(Se destaca). \u00a0 \u00a0<\/p>\n<p>25.\u00a0 \u00a0 \u00a0El 20 de diciembre de 2018, mediante comunicaci\u00f3n remitida v\u00eda correo \u00a0 electr\u00f3nico, la Asociaci\u00f3n Mutual Ser Empresa Solidaria de Salud E.S.S., alleg\u00f3 \u00a0 la informaci\u00f3n requerida en el numeral tercero del auto de pruebas. Primero, \u00a0 se\u00f1al\u00f3 que, de acuerdo al art\u00edculo 142 del Decreto 019 de 2012, Mutual Ser EPS \u00a0 no es la entidad competente para calificar la p\u00e9rdida de capacidad laboral \u00a0 ocasionada por un accidente de tr\u00e1nsito[25]. \u00a0 En ese sentido, afirm\u00f3 que \u201clo que determina cu\u00e1l es la entidad encargada de \u00a0 llevar a cabo su calificaci\u00f3n es el inter\u00e9s por el cual el solicitante requiere \u00a0 ser calificado. Para el caso en menci\u00f3n, como quiera que se trata de un seguro \u00a0 de invalidez, le corresponde a [la] aseguradora correspondiente remitirlo ante \u00a0 la junta regional de calificaci\u00f3n\u201d \u00a0 [26]. \u00a0 \u00a0<\/p>\n<p>Adicionalmente, la mencionada EPS advirti\u00f3 que la prueba pertinente y conducente \u00a0 para requerir el amparo por incapacidad permanente cubierta por el SOAT es \u00a0 \u201cla calificaci\u00f3n emitida por la Junta Regional de Invalidez, que puede ser \u00a0 solicitada (\u2026) por parte del accionante y por parte de la empresa aseguradora\u201d[27]. \u00a0 \u00a0<\/p>\n<p>Por \u00faltimo, indic\u00f3 que i) el costo del dictamen de p\u00e9rdida de \u00a0 capacidad laboral equivale a un (1) salario m\u00ednimo legal mensual vigente, y, \u00a0 ii) \u00a0que no ha recibido solicitud alguna por parte de Luis Daniel Camacho Bele\u00f1o para \u00a0 la calificaci\u00f3n de su p\u00e9rdida de capacidad laboral. \u00a0 \u00a0<\/p>\n<p>26.\u00a0 De otro lado, no \u00a0 se recibi\u00f3 respuesta por parte de la Junta Regional de Calificaci\u00f3n \u00a0 de Invalidez de Bol\u00edvar, ni de Seguros del Estado S.A. \u00a0 \u00a0<\/p>\n<p>II. CONSIDERACIONES \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Competencia \u00a0 \u00a0<\/p>\n<p>27.\u00a0 \u00a0Esta Sala de \u00a0 Revisi\u00f3n de la Corte Constitucional es competente para revisar los fallos de \u00a0 tutela proferidos dentro del tr\u00e1mite de la referencia, con fundamento en lo \u00a0 dispuesto por los art\u00edculos 86.3 y 241.9 de la Constituci\u00f3n Pol\u00edtica, en \u00a0 concordancia con los art\u00edculos 33, 34, 35 y 36 del Decreto-Ley 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Problema jur\u00eddico \u00a0 \u00a0<\/p>\n<p>28.\u00a0 \u00a0Le \u00a0 corresponder\u00eda a esta Sala de Revisi\u00f3n determinar si Seguros del Estado S.A. vulner\u00f3 los \u00a0 derechos fundamentales a la salud y debido proceso del menor Luis Daniel Camacho \u00a0 Bele\u00f1o, por: (i) negarse a realizar el dictamen de p\u00e9rdida de \u00a0 capacidad laboral en primera oportunidad y, (ii) no asumir el pago \u00a0 de los honorarios de la Junta Regional de Calificaci\u00f3n de Invalidez competente \u00a0 para la pr\u00e1ctica de dicho dictamen. \u00a0 \u00a0<\/p>\n<p>29.\u00a0 \u00a0\u00a0No obstante, en \u00a0 atenci\u00f3n a los antecedentes procesales del caso sub judice, la Sala deber\u00e1 estudiar si se configura una carencia \u00a0 actual de objeto por hecho superado. Para ello, analizar\u00e1 (i) la jurisprudencia constitucional sobre carencia \u00a0 actual de objeto y, luego, (ii) resolver\u00e1 el caso concreto. \u00a0 \u00a0<\/p>\n<p>3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Carencia actual de objeto \u00a0 \u00a0<\/p>\n<p>30.\u00a0 \u00a0 \u00a0La finalidad de la acci\u00f3n de tutela es servir de instrumento para la protecci\u00f3n \u00a0 inmediata de los derechos fundamentales, cuando estos se encuentren amenazados o \u00a0 vulnerados por la acci\u00f3n u omisi\u00f3n de una autoridad p\u00fablica o de un particular[28]. \u00a0 Por eso, si la situaci\u00f3n que genera la vulneraci\u00f3n o amenaza \u201ces superada o \u00a0 finalmente se produce el da\u00f1o que se pretend\u00eda evitar con la solicitud de \u00a0 amparo\u201d[29], \u00a0la acci\u00f3n de tutela deviene en improcedente. En ese sentido, tal circunstancia \u00a0 supone la existencia de una carencia actual de objeto. \u00a0 \u00a0<\/p>\n<p>31.\u00a0 \u00a0 \u00a0La jurisprudencia constitucional ha identificado tres hip\u00f3tesis en las cuales se \u00a0 configura el fen\u00f3meno de la carencia actual de objeto[30], a \u00a0 saber: (i) cuando se presenta un da\u00f1o consumado; (ii) \u00a0cuando acontece un hecho sobreviniente; y (iii) cuando existe un \u00a0 hecho superado[31]. \u00a0 \u00a0<\/p>\n<p>32.\u00a0 \u00a0 \u00a0En particular, la carencia actual de objeto por hecho superado tiene lugar \u00a0 cuando desaparece la afectaci\u00f3n al derecho fundamental alegado y se satisfacen \u00a0 las pretensiones del accionante[32]. Esta circunstancia puede ser \u00a0 consecuencia de \u201cla \u00a0 observancia de las pretensiones del accionante a partir de una conducta \u00a0 desplegada por el agente transgresor\u201d[33], \u00a0lo cual puede acaecer entre la presentaci\u00f3n de la tutela y la \u00a0 sentencia del juez constitucional[34]. \u00a0 \u00a0<\/p>\n<p>Cuando se encuentra demostrada esta situaci\u00f3n, el juez de \u00a0 tutela no tiene el deber de proferir un pronunciamiento de fondo[35]. \u00a0 Sin embargo, de considerarlo necesario, puede realizar observaciones sobre los \u00a0 hechos que dieron lugar a la interposici\u00f3n de la acci\u00f3n de tutela, bien sea para \u00a0 reprochar su ocurrencia, advertir sobre su falta de conformidad constitucional o \u00a0 conminar al accionado para evitar su repetici\u00f3n[36]. \u00a0 En todos los casos, sin embargo, de conformidad con la jurisprudencia \u00a0 constitucional, es necesario demostrar el acaecimiento del hecho superado[37]. \u00a0 \u00a0<\/p>\n<p>33.\u00a0 De conformidad con la jurisprudencia constitucional, se han \u00a0 diferenciado tres criterios para determinar si ha acaecido o no el fen\u00f3meno de \u00a0 la carencia actual de objeto por hecho superado, a saber[38]: \u00a0(i) \u00a0que con anterioridad a la acci\u00f3n de tutela exista una vulneraci\u00f3n o amenaza a un \u00a0 derecho fundamental del accionante, cuya protecci\u00f3n sea posteriormente \u00a0 solicitada; (ii) \u00a0que durante el tr\u00e1mite de la acci\u00f3n de tutela haya cesado la vulneraci\u00f3n o \u00a0 amenaza del derecho, y; (iii) que si la acci\u00f3n pretende el suministro de una \u00a0 prestaci\u00f3n y, \u201cdentro \u00a0 del tr\u00e1mite de dicha acci\u00f3n se satisface \u00e9sta \u00a0[advierte la Sala, \u00a0 siempre y cuando no corresponda al cumplimiento de una orden del juez de tutela], \u00a0 tambi\u00e9n se puede considerar que existe un hecho superado\u201d[39]. \u00a0 \u00a0<\/p>\n<p>34.\u00a0 De esta manera, cuando se encuentre probada alguna de estas \u00a0 circunstancias, el juez constitucional tiene el deber de declarar la carencia \u00a0 actual de objeto. De lo contrario, las decisiones y \u00f3rdenes carecer\u00edan de \u00a0 sentido ante \u201cla \u00a0 superaci\u00f3n de los hechos que dieron lugar al recurso de amparo o ante la \u00a0 satisfacci\u00f3n de las pretensiones del actor (\u2026)\u201d[40]. \u00a0 \u00a0<\/p>\n<p>35.\u00a0 \u00a0A lo dicho habr\u00eda que agregar que, para establecer si se \u00a0 configura un supuesto de carencia actual de objeto por hecho superado, es \u00a0 necesario determinar el nivel de satisfacci\u00f3n de los derechos fundamentales cuya \u00a0 protecci\u00f3n se solicita en la demanda de tutela, con miras a establecer si \u00a0 cesaron de manera definitiva los hechos perturbadores, o si las pretensiones de \u00a0 la acci\u00f3n fueron plenamente satisfechas durante el tr\u00e1mite judicial. \u00a0 \u00a0<\/p>\n<p>4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Caso concreto \u00a0 \u00a0<\/p>\n<p>36.\u00a0 \u00a0Esta acci\u00f3n de tutela fue interpuesta por la se\u00f1ora Martha \u00a0 Isabel Bele\u00f1o Hurtado, en representaci\u00f3n de su menor hijo Luis Daniel Camacho \u00a0 Bele\u00f1o, a fin de lograr el amparo de sus derechos fundamentales a la salud y \u00a0 debido proceso. A su juicio, los mencionados derechos fueron vulnerados con \u00a0 ocasi\u00f3n de la negativa de Seguros del Estado S.A. a practicar la valoraci\u00f3n de \u00a0 p\u00e9rdida de capacidad laboral del menor, o por no cancelar los honorarios para \u00a0 que se llevara a cabo la valoraci\u00f3n aludida. \u00a0 \u00a0<\/p>\n<p>37.\u00a0 \u00a0 \u00a0Luego de analizar los elementos probatorios obrantes en el expediente, la Sala \u00a0 Primera de Revisi\u00f3n de Tutelas de la Corte Constitucional encuentra que, en el \u00a0 presente asunto, Seguros del Estado S.A. vulner\u00f3 los derechos fundamentales a la \u00a0 salud y \u00a0 debido proceso del menor Luis Daniel Camacho Bele\u00f1o, por haberse negado a \u00a0 realizar el dictamen de p\u00e9rdida de capacidad laboral en primera oportunidad, as\u00ed \u00a0 como tambi\u00e9n, por no haber accedido a la solicitud de pago de honorarios a favor \u00a0 de la Junta Regional de Calificaci\u00f3n de Invalidez de Bol\u00edvar, teniendo en cuenta \u00a0 que la accionante es una persona que carece de los recursos econ\u00f3micos para \u00a0 sufragarlo. \u00a0 \u00a0<\/p>\n<p>38.\u00a0 \u00a0 \u00a0Con todo, se advierte la configuraci\u00f3n de una carencia actual de objeto por \u00a0 hecho superado, puesto que la presunta vulneraci\u00f3n de los derechos fundamentales \u00a0 alegados por el accionante ha cesado, tal y como dio cuenta la se\u00f1ora Martha \u00a0 Isabel Bele\u00f1o Hurtado en el escrito allegado en sede de revisi\u00f3n. En efecto, el \u00a0 menor Luis Daniel Camacho Bele\u00f1o ya fue valorado por la Junta Regional de \u00a0 Calificaci\u00f3n de Invalidez de Bol\u00edvar, en atenci\u00f3n a que Seguros del Estado S.A. \u00a0 sufrag\u00f3 el valor correspondiente a los honorarios de la Junta, tal como a \u00a0 continuaci\u00f3n pasa a explicarse. \u00a0 \u00a0<\/p>\n<p>39.\u00a0 \u00a0 \u00a0Primero, \u00a0el menor Luis Daniel Camacho fue valorado por la Junta Regional de \u00a0 Calificaci\u00f3n de Invalidez de Bol\u00edvar. En su solicitud de tutela, la \u00a0 se\u00f1ora Martha Isabel Bele\u00f1o Hurtado manifest\u00f3 que Seguros del Estado S.A. se \u00a0 neg\u00f3 a valorar la p\u00e9rdida de capacidad laboral de su hijo, y tampoco asumi\u00f3 el \u00a0 valor de los honorarios para que fuera examinado por la correspondiente Junta \u00a0 Regional de Calificaci\u00f3n de Invalidez. Seguros del Estado S.A. indic\u00f3 que \u00a0 \u201cpara acceder al amparo de Indemnizaci\u00f3n por Incapacidad Permanente se hace \u00a0 necesario aportar \u201coriginal del dictamen sobre la incapacidad permanente, \u00a0 expedido por las entidades autorizadas para ello de conformidad con la ley (\u2026) \u00a0 Tal como claramente lo indica el art\u00edculo 14 del Decreto 056 de 2015 literal a), \u00a0 par\u00e1grafo 1, art\u00edculo 142 del Decreto 019 de 2012, en concordancia del art\u00edculo \u00a0 1, numeral 3, literal b, y art\u00edculo 20 del Decreto 1352 de 2013\u201d[41]. \u00a0En esa medida, se\u00f1al\u00f3 que \u201cel accionante necesita una valoraci\u00f3n \u00a0 m\u00e9dica para establecer las secuelas generadas por el accidente de tr\u00e1nsito\u201d[42], \u00a0 y la compa\u00f1\u00eda aseguradora vulnera sus derechos por (i) negarse a \u00a0 realizar el dictamen, y tambi\u00e9n, (ii) por no remitirlo ante la \u00a0 Junta Regional de Calificaci\u00f3n de Invalidez de Bol\u00edvar para que esta entidad \u00a0 valorara su p\u00e9rdida de capacidad laboral[43]. \u00a0 \u00a0<\/p>\n<p>40.\u00a0 La sociedad \u00a0 accionada sustent\u00f3 su negativa en que \u201cno tiene el deber legal de asumir la \u00a0 valoraci\u00f3n y el costo de los honorarios de las Juntas de Calificaci\u00f3n de \u00a0 Invalidez, pues este costo no se encuentra establecido dentro de los amparos del \u00a0 Seguro Obligatorio de Accidentes de Tr\u00e1nsito SOAT, se\u00f1alados por las diferentes \u00a0 disposiciones legales\u201d[44]. \u00a0 \u00a0<\/p>\n<p>41.\u00a0 A prop\u00f3sito de lo \u00a0 anterior, esta Sala de Revisi\u00f3n estima conveniente precisar que las compa\u00f1\u00edas \u00a0 aseguradoras de riesgos de invalidez y muerte s\u00ed tienen el deber de realizar la \u00a0 valoraci\u00f3n de p\u00e9rdida de capacidad laboral en primera oportunidad, y por ello \u00a0 Seguros del Estado S.A. si ten\u00eda la obligaci\u00f3n de valorar al menor Luis Daniel \u00a0 Camacho Bele\u00f1o. Lo anterior, de conformidad con el siguiente marco jur\u00eddico: \u00a0 \u00a0<\/p>\n<p>Es cierto que el art\u00edculo 142 del Decreto Ley 019 de 2012, que modific\u00f3 el art\u00edculo 41 de la \u00a0 Ley 100 de 1993, se\u00f1ala que la determinaci\u00f3n de la p\u00e9rdida de capacidad laboral \u00a0 en primera oportunidad y calificaci\u00f3n del grado de invalidez de estas \u00a0 contingencias, es competencia de: (i) el Instituto de Seguros \u00a0 Sociales, (ii) la Administradora Colombiana de Pensiones \u00a0 -Colpensiones-, (iii) las Administradoras de Riesgos \u00a0 Profesionales, (iv) las Compa\u00f1\u00edas de Seguros que asuman el riesgo \u00a0 de invalidez y muerte, y, (v) las Entidades Promotoras de Salud \u00a0 -EPS-. Con todo, para efectos de tramitar el pago de la \u00a0 indemnizaci\u00f3n por incapacidad permanente causada por accidente de tr\u00e1nsito, \u00a0 \u00fanicamente, la compa\u00f1\u00eda aseguradora de invalidez y muerte, o la Junta de \u00a0 Calificaci\u00f3n de Invalidez est\u00e1n facultadas para efectuar la calificaci\u00f3n, por \u00a0 dos razones. \u00a0 \u00a0<\/p>\n<p>Las Entidades Promotoras de Servicios de Salud -EPS- tienen el deber de expedir \u00a0 el certificado m\u00e9dico emitido por el profesional de la \u00a0 salud que atendi\u00f3 la incapacidad, para acreditar la ocurrencia del siniestro[45]; \u00a0mientras que las Administradoras de Riesgos Laborales -ARL- \u00a0 (encargadas de la asunci\u00f3n de los riesgos originados en una relaci\u00f3n de \u00a0 trabajo), y, las Administradoras de Fondos de Pensiones -AFP- (responsables de \u00a0 los riesgos de vejez, invalidez o muerte de los afiliados al sistema general de \u00a0 pensiones), no se encuentran facultadas para expedir certificado m\u00e9dico o \u00a0 documento en que se valore la p\u00e9rdida de capacidad laboral sufrida por una \u00a0 persona en el marco de la reclamaci\u00f3n de las coberturas del SOAT. \u00a0 \u00a0<\/p>\n<p>42.\u00a0 \u00a0Por su parte, las Juntas Regionales de \u00a0 Calificaci\u00f3n de Invalidez son competentes para calcular y fijar el grado de \u00a0 p\u00e9rdida de capacidad laboral de una persona en cuyo favor se reclame el \u00a0 reconocimiento de los beneficios previstos para atender las consecuencias de \u00a0 accidentes automovil\u00edsticos y eventos catastr\u00f3ficos, bien sea a trav\u00e9s de la \u00a0 Subcuenta de Riesgos Catastr\u00f3ficos y Accidentes de Tr\u00e1nsito del Fondo de \u00a0 Solidaridad y Garant\u00eda o cualquier compa\u00f1\u00eda de seguros[46]. \u00a0 \u00a0<\/p>\n<p>43.\u00a0 \u00a0 \u00a0De lo anterior resulta claro que las compa\u00f1\u00edas aseguradoras de invalidez y \u00a0 muerte ser\u00e1n competentes en primera oportunidad, para calificar directamente la \u00a0 p\u00e9rdida de capacidad laboral de la v\u00edctima, o por medio de un profesional de la \u00a0 salud externo[47], \u00a0 y en el evento en que la valoraci\u00f3n de p\u00e9rdida de capacidad laboral proferida en \u00a0 primera oportunidad sea impugnada, la Junta Regional de Calificaci\u00f3n de \u00a0 Invalidez conocer\u00e1 en primera instancia y emitir\u00e1 su dictamen. \u00a0 \u00a0<\/p>\n<p>De igual manera, la compa\u00f1\u00eda aseguradora cuenta con la posibilidad de remitir al \u00a0 solicitante de manera directa ante la Junta \u00a0 Regional de Calificaci\u00f3n de Invalidez competente para ser calificado en primera \u00a0 instancia, y si esta decisi\u00f3n es impugnada, conocer\u00e1 la Junta Nacional de \u00a0 Calificaci\u00f3n de Invalidez en segunda instancia. [48] \u00a0 \u00a0<\/p>\n<p>44.\u00a0 \u00a0 \u00a0As\u00ed las cosas, esta Sala advierte que la compa\u00f1\u00eda Seguros del Estado S.A. si \u00a0 vulner\u00f3 los derechos fundamentales del menor Luis Daniel Camacho Bele\u00f1o, pues \u00a0 era su obligaci\u00f3n realizar la valoraci\u00f3n de p\u00e9rdida de capacidad laboral del \u00a0 menor, o remitirlo ante la Junta Regional de Calificaci\u00f3n de Invalidez \u00a0 competente. \u00a0 \u00a0<\/p>\n<p>45.\u00a0 \u00a0 \u00a0Ahora bien, al descender al asunto sub judice, se constata que la \u00a0 pretensi\u00f3n de la accionante consistente en que su hijo Luis Daniel fuera \u00a0 valorado, ya fue satisfecha. Esto por cuanto, tal y como fue informado por la \u00a0 actora en sede de revisi\u00f3n, Seguros del Estado S.A. hizo valorar la p\u00e9rdida de \u00a0 capacidad laboral del menor, al remitirlo ante la Junta Regional de Calificaci\u00f3n \u00a0 de Invalidez de Bol\u00edvar. \u00a0 \u00a0<\/p>\n<p>46.\u00a0 \u00a0 \u00a0Segundo, \u00a0la compa\u00f1\u00eda aseguradora Seguros del Estado S.A. sufrag\u00f3 el valor de los \u00a0 honorarios de la Junta Regional de Calificaci\u00f3n de Invalidez de Bol\u00edvar. \u00a0 Sobre el \u00a0 pago de honorarios a favor de la Junta de Calificaci\u00f3n de Invalidez para la \u00a0 realizaci\u00f3n del dictamen de p\u00e9rdida de capacidad laboral, debe precisarse que, en el evento en que las compa\u00f1\u00edas aseguradoras de \u00a0 riesgos de invalidez y muerte no realicen la valoraci\u00f3n requerida, el aspirante \u00a0 a beneficiario se encuentra habilitado para acudir ante la Junta Regional de \u00a0 Calificaci\u00f3n de Invalidez para obtener la pr\u00e1ctica del dictamen en primera \u00a0 instancia, y asumir directamente el pago de los honorarios con posibilidad de \u00a0 recobro[49]. Con todo, cuando el solicitante \u00a0 sea una persona en situaci\u00f3n de vulnerabilidad, que no cuente con los recursos \u00a0 econ\u00f3micos para sufragar el costo de la valoraci\u00f3n, las aseguradoras deber\u00e1n \u00a0 asumir el pago de los honorarios a fin de que este pueda iniciar la reclamaci\u00f3n \u00a0 de la indemnizaci\u00f3n por incapacidad permanente[50]. \u00a0 \u00a0<\/p>\n<p>47.\u00a0 \u00a0En el caso concreto, en concepto de la se\u00f1ora Bele\u00f1o Hurtado, \u00a0 la entidad accionada vulner\u00f3 los derechos fundamentales a la salud y debido \u00a0 proceso de su hijo, por \u201cla negativa y el incumplimiento de valorar a la \u00a0 v\u00edctima en primera instancia como lo ordena el decreto 056 de 2015\u201d[51], \u00a0y por la renuencia a pagar los honorarios requeridos para que la Junta Regional \u00a0 de Calificaci\u00f3n de Invalidez de Bol\u00edvar practicara el dictamen de p\u00e9rdida de \u00a0 capacidad laboral a Luis Daniel. As\u00ed, en los t\u00e9rminos de la acci\u00f3n de tutela \u00a0 presentada por la se\u00f1ora Bele\u00f1o Hurtado, es claro que su pretensi\u00f3n estaba \u00a0 encaminada a obtener que Seguros del Estado S.A. pagara a favor de la Junta \u00a0 Regional de Invalidez de Bol\u00edvar el valor de los honorarios requeridos para la \u00a0 pr\u00e1ctica del dictamen de p\u00e9rdida de capacidad laboral de su hijo Luis Daniel. \u00a0 \u00a0<\/p>\n<p>48.\u00a0 \u00a0Al respecto, esta Sala evidencia que, en el tr\u00e1mite de \u00a0 revisi\u00f3n, la actora manifest\u00f3 expresamente que \u201cLuis Daniel ya fue valorado \u00a0 ante la Junta Regional de Calificaci\u00f3n de Invalidez de Bol\u00edvar y se encuentra \u00a0 esperando los resultados, toda vez que la aseguradora cancelo (sic) los \u00a0 honorarios por orden de un fallo de tutela\u201d. Frente a este \u00faltimo punto es \u00a0 necesario aclarar que, si bien es cierto Seguros del Estado S.A. deb\u00eda sufragar \u00a0 el costo del dictamen de p\u00e9rdida de capacidad laboral solicitado por la \u00a0 tutelante, la accionada satisfizo completamente lo pretendido por la actora, no \u00a0 en cumplimiento de una orden del juez de tutela -pues el amparo otorgado por el \u00a0a quo fue revocado en segunda instancia-, sino que accedi\u00f3 motu \u00a0 proprio a la prestaci\u00f3n solicitada. En otras palabras, se advierte \u201cla observancia de las \u00a0 pretensiones del accionante a partir de una conducta desplegada por el agente \u00a0 transgresor\u201d[52]. \u00a0 \u00a0<\/p>\n<p>49.\u00a0 \u00a0De conformidad con lo anterior, la Sala concluye que en el \u00a0 presente asunto la compa\u00f1\u00eda aseguradora vulner\u00f3 los derechos fundamentales a la \u00a0 salud y debido proceso del menor Luis Daniel Camacho Bele\u00f1o, pero se configur\u00f3 \u00a0 una carencia actual de objeto por hecho superado, habida cuenta de que entre el \u00a0 momento de la interposici\u00f3n de la solicitud de amparo y el momento del fallo, se \u00a0 satisfizo por completo la pretensi\u00f3n contenida en la demanda. Esto por cuanto, \u00a0 se reitera, la compa\u00f1\u00eda aseguradora Seguros del Estado S.A. cancel\u00f3 el valor de \u00a0 honorarios correspondientes a favor de la Junta Regional de Calificaci\u00f3n de \u00a0 Invalidez de Bol\u00edvar, y como consecuencia de ello, al menor Luis Daniel Camacho \u00a0 Bele\u00f1o ya le fue dictaminada su p\u00e9rdida de capacidad laboral. En esa medida, \u00a0 cualquier orden que impartiese la Sala al respecto resultar\u00eda inocua. \u00a0 \u00a0<\/p>\n<p>5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0S\u00edntesis de la decisi\u00f3n \u00a0 \u00a0<\/p>\n<p>50.\u00a0 \u00a0La se\u00f1ora Martha Isabel Bele\u00f1o Hurtado formul\u00f3 acci\u00f3n de \u00a0 tutela en contra de Seguros del Estado S.A. con la finalidad de lograr el amparo \u00a0 de los derechos a la salud y debido proceso de su hijo Luis Daniel Camacho \u00a0 Bele\u00f1o. A su juicio, estos fueron vulnerados por la sociedad accionada, quien se \u00a0 neg\u00f3 a valorar la p\u00e9rdida de capacidad laboral del menor y remitirlo ante la \u00a0 Junta Regional de Calificaci\u00f3n de Invalidez de Bol\u00edvar para que lo dictaminara, \u00a0 asumiendo el costo de los honorarios correspondientes a la pr\u00e1ctica del dictamen \u00a0 m\u00e9dico. \u00a0 \u00a0<\/p>\n<p>51.\u00a0 \u00a0El juez de primera instancia ampar\u00f3 los derechos fundamentales \u00a0 del accionante por considerar que la compa\u00f1\u00eda aseguradora si estaba en la \u00a0 obligaci\u00f3n legal de asumir el costo de los honorarios ante la Junta de \u00a0 Calificaci\u00f3n de Invalidez de Bol\u00edvar.\u00a0 Sin embargo, tras la impugnaci\u00f3n \u00a0 presentada por Seguros del Estado S.A., el ad quem revoc\u00f3 la decisi\u00f3n, y \u00a0 en consecuencia, neg\u00f3 el amparo pretendido. Fundament\u00f3 su decisi\u00f3n en que la ley \u00a0 no establece la obligaci\u00f3n para las aseguradoras del SOAT de calificar la \u00a0 p\u00e9rdida de capacidad laboral en primera oportunidad y menos a\u00fan el pago de los \u00a0 honorarios a favor de las Juntas de Calificaci\u00f3n de Invalidez. \u00a0 \u00a0<\/p>\n<p>52.\u00a0 \u00a0Con fundamento en las pruebas decretadas en sede de revisi\u00f3n, \u00a0 la Sala concluy\u00f3 que Seguros del Estado S.A. vulner\u00f3 los derechos fundamentales \u00a0 a la salud y debido proceso del menor Luis Daniel Camacho Bele\u00f1o, no obstante \u00a0 encontr\u00f3 acreditada la configuraci\u00f3n de una carencia actual de objeto por hecho \u00a0 superado. Lo anterior por cuanto la mencionada compa\u00f1\u00eda aseguradora sufrag\u00f3 el \u00a0 valor de los honorarios de la Junta Regional de Invalidez de Bol\u00edvar, y en \u00a0 consecuencia, dicha sociedad llev\u00f3 a cabo la valoraci\u00f3n de la p\u00e9rdida de \u00a0 capacidad laboral al menor Luis Daniel Camacho Bele\u00f1o. \u00a0 \u00a0<\/p>\n<p>53.\u00a0 \u00a0As\u00ed las cosas, al evidenciar que las pretensiones del \u00a0 tutelante fueron satisfechas por la entidad accionada, la Sala ordenar\u00e1 revocar \u00a0 la decisi\u00f3n del a quo y, declarar\u00e1 la carencia actual de objeto por hecho \u00a0 superado. \u00a0 \u00a0<\/p>\n<p>III.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Decisi\u00f3n \u00a0 \u00a0<\/p>\n<p>54.\u00a0 \u00a0 \u00a0En m\u00e9rito de lo expuesto, la Sala Primera de Revisi\u00f3n de la Corte \u00a0 Constitucional, administrando justicia en nombre del pueblo y por mandato de la \u00a0 Constituci\u00f3n, \u00a0 \u00a0<\/p>\n<p>RESUELVE \u00a0 \u00a0<\/p>\n<p>Primero.- REVOCAR la sentencia proferida el 2 de agosto \u00a0 de 2018 por el Juez Primero Penal del Circuito con funciones de conocimiento de \u00a0 Cartagena, y en su lugar, CONFIRMAR la sentencia dictada el 20 de junio \u00a0 de 2018 por el Juez Noveno Penal Municipal de Cartagena, por lo expuesto en la \u00a0 parte motiva de esta decisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>Segundo.- DECLARAR la CARENCIA ACTUAL DE OBJETO por hecho \u00a0 superado en el presente asunto, por las razones expuestas en esta providencia. \u00a0 \u00a0<\/p>\n<p>Tercero.- LIBRAR,\u00a0por Secretar\u00eda General, la comunicaci\u00f3n de que trata el art\u00edculo 36 \u00a0 del Decreto 2591 de 1991, para los efectos all\u00ed contemplados. \u00a0 \u00a0<\/p>\n<p>Comun\u00edquese y c\u00famplase, \u00a0 \u00a0<\/p>\n<p>CARLOS BERNAL PULIDO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>DIANA FAJARDO RIVERA \u00a0 \u00a0<\/p>\n<p>LUIS GUILLERMO GUERRERO P\u00c9REZ \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0 \u00a0<\/p>\n<p>Secretaria General \u00a0 \u00a0<\/p>\n<p>[1] Integrada por los Magistrados \u00a0 Gloria Stella Ortiz Delgado y Antonio Jos\u00e9 Lizarazo Ocampo. \u00a0 \u00a0<\/p>\n<p>[2] El menor naci\u00f3 el 19 \u00a0 de junio de 2007, seg\u00fan consta en la tarjeta de identidad y registro civil de \u00a0 nacimiento que obran a folios 9 y 10 del cuaderno 1, respectivamente. \u00a0 \u00a0<\/p>\n<p>[3] Folios 15-17, cuaderno \u00a0 1. \u00a0 \u00a0<\/p>\n<p>[4] Folio 11, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[5] Folios 13-14, cuaderno \u00a0 1. \u00a0 \u00a0<\/p>\n<p>[6] Folios 18-19, cuaderno \u00a0 1. \u00a0 \u00a0<\/p>\n<p>[7] Folio 1, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[9] Folio 4, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[10] Folios 39 y 43-45, \u00a0 cuaderno 1 \u00a0 \u00a0<\/p>\n<p>[11] Folio 55, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[12] Ib\u00edd. \u00a0 \u00a0<\/p>\n<p>[13] Folios 74-84, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[14] La \u00a0 acci\u00f3n de tutela presentada por la se\u00f1ora Martha Isabel Bele\u00f1o Hurtado fue \u00a0 admitida por el Juzgado Noveno Penal Municipal de Cartagena el 17 de mayo de \u00a0 2018 (Folio 39, Cuaderno 1). Sin embargo, mediante auto del 31 de mayo de 2018, \u00a0 el juzgado declar\u00f3 la nulidad de todo lo actuado desde el auto admisorio de la \u00a0 tutela, habida cuenta de que no se hab\u00eda notificado en debida forma a la \u00a0 accionada Seguros del Estado S.A. (Folios 43-45, cuaderno 1). \u00a0 \u00a0<\/p>\n<p>[15] Folios 74-84, cuaderno \u00a0 1. \u00a0 \u00a0<\/p>\n<p>[16] Folios 98-105, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[17] Folio 91, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[18] \u00a0\u201cART\u00cdCULO 142. CALIFICACI\u00d3N DEL ESTADO DE INVALIDEZ. El \u00a0 art\u00edculo 41 de la Ley 100 de \u00a0 1993, modificado por el art\u00edculo 52 de la Ley 962 de \u00a0 2005, quedar\u00e1 as\u00ed: El estado de invalidez ser\u00e1 determinado de conformidad con lo \u00a0 dispuesto en los art\u00edculos siguientes y con base en el manual \u00fanico para la \u00a0 calificaci\u00f3n de invalidez vigente a la fecha de calificaci\u00f3n. Este manual ser\u00e1 \u00a0 expedido por el Gobierno Nacional y deber\u00e1 contemplar los criterios t\u00e9cnicos de \u00a0 evaluaci\u00f3n para calificar la imposibilidad que tenga el afectado para desempe\u00f1ar \u00a0 su trabajo por p\u00e9rdida de su capacidad laboral. Corresponde al Instituto de \u00a0 Seguros Sociales, Administradora Colombiana de Pensiones -COLPENSIONES-, a las \u00a0 Administradoras de Riesgos Profesionales &#8211; ARP-, a las Compa\u00f1\u00edas de Seguros que \u00a0 asuman el riesgo de invalidez y muerte, y a las Entidades Promotoras de Salud \u00a0 EPS, determinar en una primera oportunidad la p\u00e9rdida de capacidad laboral y \u00a0 calificar el grado de invalidez y el origen de estas contingencias. \u00a0 \u00a0\u00a0<\/p>\n<p>En caso de que el \u00a0 interesado no est\u00e9 de acuerdo con la calificaci\u00f3n deber\u00e1 manifestar su \u00a0 inconformidad dentro de los diez (10) d\u00edas siguientes y la entidad deber\u00e1 \u00a0 remitirlo a las Juntas Regionales de Calificaci\u00f3n de Invalidez del orden \u00a0 regional dentro de los cinco (5) d\u00edas siguientes, cuya decisi\u00f3n ser\u00e1 apelable \u00a0 ante la Junta Nacional de Calificaci\u00f3n de Invalidez, la cual decidir\u00e1 en un \u00a0 t\u00e9rmino de cinco (5) d\u00edas. Contra dichas decisiones proceden las acciones \u00a0 legales. \u00a0 \u00a0<\/p>\n<p>El acto que \u00a0 declara la invalidez que expida cualquiera de las anteriores entidades, deber\u00e1 \u00a0 contener expresamente los fundamentos de hecho y de derecho que dieron origen a \u00a0 esta decisi\u00f3n, as\u00ed como la forma y oportunidad en que el interesado puede \u00a0 solicitar la calificaci\u00f3n por parte de la Junta Regional y la facultad de \u00a0 recurrir esta calificaci\u00f3n ante la Junta Nacional (\u2026)\u201d. \u00a0 \u00a0<\/p>\n<p>[19] Folios 98-105, \u00a0 cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[20] Folio 105, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[21] Ib\u00edd. \u00a0 \u00a0<\/p>\n<p>[22] Folios 16-17, cuaderno \u00a0 principal. \u00a0 \u00a0<\/p>\n<p>[23] Folios 24-26, cuaderno \u00a0 principal. \u00a0 \u00a0<\/p>\n<p>[24] Folio 25, cuaderno \u00a0 principal. \u00a0 \u00a0<\/p>\n<p>[25] Folios 36-38, cuaderno principal. \u00a0 \u00a0<\/p>\n<p>[26] Folio 37 Vto., cuaderno principal. \u00a0 \u00a0<\/p>\n<p>[27] Folio 38, cuaderno principal. \u00a0 \u00a0<\/p>\n<p>[28] Art. 86 de la C.P.: \u201cToda persona tendr\u00e1 acci\u00f3n de tutela para reclamar ante los jueces, \u00a0 en todo momento y lugar, mediante un procedimiento preferente y sumario, por s\u00ed \u00a0 misma o por quien act\u00fae a su nombre, la protecci\u00f3n inmediata de sus derechos \u00a0 constitucionales fundamentales, cuando quiera que \u00e9stos resulten vulnerados o \u00a0 amenazados por la acci\u00f3n o la omisi\u00f3n de cualquier autoridad p\u00fablica\u201d \u00a0 \u00a0<\/p>\n<p>[29] Sentencias T-369 de 2017, T-149 de 2018, y T-319 de \u00a0 2018, entre otras. \u00a0 \u00a0<\/p>\n<p>[30] Sentencia T-625 de 2017. \u00a0 \u00a0<\/p>\n<p>[31] Ver las sentencias T-261 de 2017, T-481 de 2016, T-321 de 2016 \u00a0 y T-200 de 2013. \u00a0 \u00a0<\/p>\n<p>[32] Con relaci\u00f3n a este supuesto, la Corte Constitucional, \u00a0 en la Sentencia SU 540 de 2007, se\u00f1al\u00f3: \u201cel hecho superado se presenta cuando, por la acci\u00f3n u omisi\u00f3n (seg\u00fan \u00a0 sea el requerimiento del actor en la tutela) del obligado, se supera la \u00a0 afectaci\u00f3n de tal manera que \u2018carece\u2019 de objeto el pronunciamiento del juez. La \u00a0 jurisprudencia de la Corte ha comprendido la expresi\u00f3n hecho superado en el \u00a0 sentido obvio de las palabras que componen la expresi\u00f3n, es decir, dentro del \u00a0 contexto de la satisfacci\u00f3n de lo pedido en la tutela.\u201d \u00a0 \u00a0<\/p>\n<p>[33] Sentencias T-238 \u00a0 de 2017 y T-011 de 2016. \u00a0 \u00a0<\/p>\n<p>[34] Sentencias T-715 \u00a0 de 2017, T-238 de 2017 y T-047 de 2016. \u00a0 \u00a0<\/p>\n<p>[35] Sentencia T-011 \u00a0 de 2016. \u00a0 \u00a0<\/p>\n<p>[36] Sentencia T-970 \u00a0 de 2014. \u00a0 \u00a0<\/p>\n<p>[37] Ver sentencias T-011 de 2016,\u00a0SU-225 de 2013, T-856 de 2012, T-035 de 2011, \u00a0 T-1027 de 2010, T-170 de 2009 y T-515 de 2007. \u00a0 \u00a0<\/p>\n<p>[38] Ver sentencias T-375 de 2017, T-330 de 2017, T-238 de 2017, \u00a0 T-021 de 2017, T-695 de 2016 y T-059 de 2016. \u00a0 \u00a0<\/p>\n<p>[39] Sentencia T-045 de 2008. \u00a0 \u00a0<\/p>\n<p>[40] Sentencia SU-771 de 2014. \u00a0 \u00a0<\/p>\n<p>[41] Folio 1, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[42] Folio 2, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[43] Folios 3-4, cuaderno \u00a0 1. \u00a0 \u00a0<\/p>\n<p>[44] Folio 55, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>[45] Art\u00edculo 7 Decreto 056 \u00a0 de 2015: \u201clos servicios m\u00e9dicos, quir\u00fargicos, \u00a0 farmac\u00e9uticos y hospitalarios, suministrados a la v\u00edctima por un prestador de \u00a0 servicios de salud habilitado, destinados a lograr su estabilizaci\u00f3n, \u00a0 tratamiento y la rehabilitaci\u00f3n de sus secuelas y de las patolog\u00edas generadas \u00a0 como consecuencia de los mencionados eventos, as\u00ed como el tratamiento de las \u00a0 complicaciones resultantes de dichos eventos a las patolog\u00edas que esta tra\u00eda\u201d. \u00a0 \u00a0<\/p>\n<p>[46] Sentencia T-282 de 2010. \u00a0 \u00a0<\/p>\n<p>[47] \u201cDebidamente autorizado para \u00a0 funcionar\u201d, seg\u00fan \u00a0 el numeral 1 literal b del art\u00edculo 194 del Estatuto Org\u00e1nico del Sistema \u00a0 Financiero. \u00a0 \u00a0<\/p>\n<p>[48] Sentencia T-400 de \u00a0 2017. \u00a0 \u00a0<\/p>\n<p>[49] El art\u00edculo 50 del Decreto 2463 de 2001, adiciona que \u00a0 el aspirante a beneficiario tambi\u00e9n puede sufragar los honorarios de la Junta de \u00a0 Calificaci\u00f3n de Invalidez.\u00a0 \u00a0 \u00a0<\/p>\n<p>[50] Postura fijada en \u00a0 sentencias T-282 de 2010, T-045 de 2013 y T-400 de 2017. \u00a0 \u00a0<\/p>\n<p>[51] Folio 4, cuaderno 1. \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-076-19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 Sentencia T-076\/19 \u00a0 \u00a0 DERECHO A LA CALIFICACION DE LA PERDIDA DE LA CAPACIDAD LABORAL DE MENOR, QUIEN \u00a0 SUFRIO ACCIDENTE DE TRANSITO \u00a0 \u00a0 CALIFICACION DE LA PERDIDA DE LA CAPACIDAD LABORAL-Determinaci\u00f3n de \u00a0 la competencia en los eventos de accidentes de tr\u00e1nsito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126],"tags":[],"class_list":["post-26656","post","type-post","status-publish","format-standard","hentry","category-tutelas-2019"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/26656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=26656"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/26656\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=26656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=26656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=26656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}