{"id":26786,"date":"2024-07-02T17:18:14","date_gmt":"2024-07-02T17:18:14","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/07\/02\/t-302-19\/"},"modified":"2024-07-02T17:18:14","modified_gmt":"2024-07-02T17:18:14","slug":"t-302-19","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-302-19\/","title":{"rendered":"T-302-19"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-302-19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia T-302\/19 \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA ACTO ADMINISTRATIVO QUE ORDENA O NIEGA \u00a0 TRASLADO DE SERVIDOR PUBLICO-Procedencia excepcional \u00a0 \u00a0<\/p>\n<p>La \u00a0 jurisprudencia de la Corte Constitucional ha establecido, por regla general, que \u00a0 no procede la acci\u00f3n de tutela en contra de los actos administrativos de \u00a0 car\u00e1cter particular y concreto, pues el debate en torno a su legalidad con \u00a0 ocasi\u00f3n de su aplicaci\u00f3n o interpretaci\u00f3n corresponde a la Jurisdicci\u00f3n de lo \u00a0 Contencioso Administrativo. No obstante, trat\u00e1ndose de actos administrativos de \u00a0 car\u00e1cter particular y concreto que presuntamente lesionan los derechos de la \u00a0 carrera judicial, este Tribunal ha aceptado la procedencia excepcional de la \u00a0 acci\u00f3n de tutela como mecanismo definitivo, a fin de salvaguardar el principio \u00a0 del m\u00e9rito, toda vez que\u00a0\u201ces el \u00fanico criterio que debe regir el ingreso, la permanencia y el \u00a0 ascenso en la carrera judicial\u201d \u00a0 \u00a0<\/p>\n<p>SOLICITUD DE \u00a0 TRASLADO DE SERVIDOR JUDICIAL POR RAZONES DE SALUD-Requisitos \u00a0 \u00a0<\/p>\n<p>La solicitud de traslado por razones de salud \u00a0 tendr\u00e1 que ser dirigida y presentada a la Unidad de Administraci\u00f3n de la Carrera \u00a0 Judicial para el respectivo tr\u00e1mite y concepto de la Sala Administrativa del \u00a0 Consejo Superior de la Judicatura. Dicho concepto debe contar con el \u00a0 cumplimiento de los siguientes aspectos, entre otros: (a) el diagn\u00f3stico m\u00e9dico \u00a0 sobre las condiciones de salud que se invocan, cuya fecha de expedici\u00f3n no puede \u00a0 superar los tres (3) meses salvo que se trate de enfermedades cr\u00f3nicas, \u00a0 progresivas, degenerativas o cong\u00e9nitas, en cuyo caso la vigencia del dictamen \u00a0 m\u00e9dico puede ser superior a los tres (3) meses sin sobrepasar los seis (6) \u00a0 meses, debe ser emitido por la entidad promotora de salud (EPS \u2013 IPS) o por la \u00a0 administradora de riesgos profesionales (ARP) a la cual se encuentre afiliado el \u00a0 servidor en el que se recomiende expresamente el traslado por la imposibilidad \u00a0 de continuar desempe\u00f1ando el cargo del cual es titular; (b) la acreditaci\u00f3n del \u00a0 parentesco cuando se trate de enfermedades del c\u00f3nyuge, compa\u00f1era o compa\u00f1ero \u00a0 permanente, descendientes, ascendientes en primer grado de consanguinidad o \u00a0 \u00fanico civil; y (c) en caso de no ser atendida la prescripci\u00f3n m\u00e9dica, la Unidad \u00a0 de Administraci\u00f3n de Carrera Judicial le ofrecer\u00e1 las vacantes existentes al \u00a0 momento, a efectos de obtener el consentimiento expreso del servidor. \u00a0 \u00a0<\/p>\n<p>TRASLADO DE SERVIDOR JUDICIAL POR RAZONES DE \u00a0 SALUD-Marco normativo \u00a0 \u00a0<\/p>\n<p>SOLICITUD DE TRASLADO POR RAZONES DE SALUD DE \u00a0 MAGISTRADOS Y JUECES-Debe ser estudiada por la Sala Administrativa del \u00a0 Consejo Superior de la Judicatura \u00a0 \u00a0<\/p>\n<p>Las \u00a0 peticiones de traslado deben ser estudiadas por la Sala Administrativa del \u00a0 Consejo Superior de la Judicatura \u2013Unidad de Administraci\u00f3n de Carrera \u00a0 Judicial\u2013, entidad que debe valorar, cuando las solicitudes sean por razones de \u00a0 salud, documentos tales como los dict\u00e1menes m\u00e9dicos que acreditan el problema de \u00a0 salud del funcionario o de sus familiares y la recomendaci\u00f3n de traslado, la \u00a0 existencia del certificado de vacancia definitiva del cargo al que se pretende \u00a0 el traslado y la manifestaci\u00f3n expresa del deseo del funcionario de ser \u00a0 trasladado a la plaza que se encuentra vacante \u00a0 \u00a0<\/p>\n<p>Referencia: \u00a0 Expediente T-7. 141.600 \u00a0 \u00a0<\/p>\n<p>Acci\u00f3n de tutela \u00a0 interpuesta por \u00c1lvaro Vincos Urue\u00f1a contra la Corte Suprema de Justicia \u2013 Sala \u00a0 Plena. \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 Ponente: \u00a0 \u00a0<\/p>\n<p>Bogot\u00e1, D.C., diez (10) de julio de dos \u00a0 mil diecinueve (2019) \u00a0 \u00a0<\/p>\n<p>La Sala Cuarta de Revisi\u00f3n de la Corte \u00a0 Constitucional, integrada por la magistrada Gloria Stella Ortiz Delgado y los \u00a0 magistrados Antonio Jos\u00e9 Lizarazo Ocampo y Alejandro Linares Cantillo, quien la \u00a0 preside, en ejercicio de sus competencias constitucionales y legales, ha \u00a0 proferido la siguiente: \u00a0 \u00a0<\/p>\n<p>SENTENCIA \u00a0 \u00a0<\/p>\n<p>En el tr\u00e1mite de revisi\u00f3n de los fallos \u00a0 proferidos el 10 de mayo y el 15 de noviembre de 2018 por la Corte Suprema de \u00a0 Justicia en sus Salas de Casaci\u00f3n Penal y Civil, respectivamente, dentro del \u00a0 proceso de tutela promovido por el se\u00f1or \u00c1lvaro Vincos Urue\u00f1a contra la Corte \u00a0 Suprema de Justicia \u2013 Sala Plena. \u00a0 \u00a0<\/p>\n<p>I.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0ANTECEDENTES \u00a0 \u00a0<\/p>\n<p>A.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0LA DEMANDA DE TUTELA \u00a0 \u00a0<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El 3 de abril de 2018, el se\u00f1or \u00c1lvaro Vincos \u00a0 Urue\u00f1a, personalmente y actuando en calidad de Magistrado de la Sala \u00danica del \u00a0 Tribunal Superior del Distrito Judicial de Yopal, present\u00f3 acci\u00f3n de tutela \u00a0 contra la Corte Suprema de Justicia \u2013 Sala Plena al considerar vulnerados sus \u00a0 derechos fundamentales al debido proceso administrativo, a la igualdad, a la \u00a0 salud y al trabajo en condiciones dignas, toda vez que la autoridad judicial \u00a0 demandada neg\u00f3 el traslado solicitado para el cargo vacante de Magistrado de la \u00a0 Sala Penal del Tribunal Superior del Distrito Judicial de Bogot\u00e1. Conforme con \u00a0 lo anterior, el accionante solicit\u00f3 al juez de tutela que ordene a la Corte \u00a0 Suprema de Justicia \u2013 Sala Plena, dentro de las cuarenta y ocho horas siguientes \u00a0 a la notificaci\u00f3n de la sentencia, proferir el acto administrativo que le \u00a0 permita trasladarse al Magistrado \u00c1lvaro Vincos Urue\u00f1a del Tribunal Superior del \u00a0 Distrito Judicial de Yopal al Tribunal Superior del Distrito Judicial de Bogot\u00e1, \u00a0 en la vacante del doctor Orlando Mu\u00f1oz Neira[1]. \u00a0 \u00a0<\/p>\n<p>B.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0HECHOS RELEVANTES \u00a0 \u00a0<\/p>\n<p>2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El 5 de junio de 2017, el Magistrado de la Sala \u00a0 \u00danica del Tribunal Superior del Distrito Judicial de Yopal, \u00c1lvaro Vincos \u00a0 Urue\u00f1a, solicit\u00f3 a la Unidad de Administraci\u00f3n de Carrera Judicial del Consejo \u00a0 Superior de la Judicatura el visto bueno para el traslado a la Sala Penal del \u00a0 Tribunal Superior del Distrito Judicial de Bogot\u00e1, vacante desde junio de 2017, \u00a0 por razones de salud[2]. \u00a0 \u00a0<\/p>\n<p>3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El 27 de julio de 2017, la Unidad de \u00a0 Administraci\u00f3n de Carrera Judicial del Consejo Superior de la Judicatura otorg\u00f3 \u00a0 concepto favorable al traslado requerido por el accionante y lo remiti\u00f3 a la \u00a0 Corte Suprema de Justicia mediante oficio CSO17-1957[3]. \u00a0 \u00a0<\/p>\n<p>4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El 22 de noviembre de 2017, el se\u00f1or Vincos \u00a0 Urue\u00f1a formul\u00f3 petici\u00f3n ante la presidencia de la Corte Suprema de Justicia a \u00a0 fin de ser informado sobre el traslado solicitado[4]. \u00a0 \u00a0<\/p>\n<p>5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El 6 de diciembre de 2017, en respuesta de la \u00a0 solicitud mencionada, la presidencia de la Corte Suprema de Justicia comunic\u00f3 \u00a0 que, mediante plenaria celebrada el 28 de septiembre de 2017, se someti\u00f3 a \u00a0 consideraci\u00f3n el traslado requerido por el se\u00f1or Vincos Urue\u00f1a y luego de \u00a0 realizar la votaci\u00f3n respectiva \u201cno obtuvo los votos m\u00ednimos requeridos, por \u00a0 lo que se decidi\u00f3 no trasladarlo a la vacante de la Sala Penal del Tribunal \u00a0 Superior del Distrito Judicial de Bogot\u00e1\u201d. Asimismo, se precis\u00f3 que ning\u00fan \u00a0 otro funcionario aspir\u00f3 al traslado de la misma vacante, que el Consejo Superior \u00a0 de la Judicatura no ha reportado una lista de elegibles para la vacante en \u00a0 menci\u00f3n y que, para ese momento, el cargo de Magistrado de la Sala Penal del \u00a0 Tribunal Superior del Distrito Judicial de Bogot\u00e1 estaba siendo ocupado por \u00a0 Mar\u00eda Stella Jara Guti\u00e9rrez, en provisionalidad[5]. \u00a0 \u00a0<\/p>\n<p>6.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Acorde con los documentos aportados al \u00a0 expediente, el se\u00f1or \u00c1lvaro Vincos Urue\u00f1a se encuentra vinculado a la Rama \u00a0 Judicial desde el 6 de mayo de 2015 como Magistrado de la Sala \u00danica del \u00a0 Tribunal Superior del Distrito Judicial de Yopal[6]. \u00a0 Padece de sinusitis y rinitis cr\u00f3nica, raz\u00f3n por la cual le ha sido recomendado \u00a0 un traslado de residencia y reubicaci\u00f3n laboral a clima templado o fr\u00edo[7]. \u00a0 \u00a0<\/p>\n<p>C.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0DECISIONES JUDICIALES OBJETO DE REVISI\u00d3N \u00a0 \u00a0<\/p>\n<p>Decisi\u00f3n de primera instancia: Corte \u00a0 Suprema de Justicia &#8211; Sala de Casaci\u00f3n Penal[8] \u00a0 \u00a0<\/p>\n<p>7.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El 10 de mayo de 2018, la Corte Suprema de \u00a0 Justicia \u2013 Sala de Casaci\u00f3n Penal, integrada por conjueces, declar\u00f3 improcedente \u00a0 la acci\u00f3n de tutela incoada por el se\u00f1or Vincos Urue\u00f1a al considerar que el \u00a0 oficio mediante el cual la Sala Plena de la Corte Suprema de Justicia deneg\u00f3 el \u00a0 traslado solicitado es un acto administrativo demandable ante la Jurisdicci\u00f3n de \u00a0 lo Contencioso Administrativo a trav\u00e9s del medio de control de nulidad y \u00a0 restablecimiento del derecho. De otro lado, indic\u00f3 que la acci\u00f3n de tutela no \u00a0 proced\u00eda como mecanismo transitorio toda vez que no se encontraba vigente el \u00a0 medio judicial ordinario, pues oper\u00f3 la caducidad del medio de control de \u00a0 nulidad y restablecimiento del derecho el 6 de abril de 2018 al cumplirse el \u00a0 t\u00e9rmino de los cuatro (4) meses, desde la recepci\u00f3n del oficio, para \u00a0 controvertirse. \u00a0 \u00a0<\/p>\n<p>8.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0No obstante lo anterior, advirti\u00f3 que la negativa \u00a0 de la Sala Plena de la Corte Suprema de Justicia[9] no result\u00f3 caprichosa en \u00a0 tanto (i) se fund\u00f3 en la naturaleza de las enfermedades que padece el actor, \u00a0 pues ni la sinusitis cr\u00f3nica ni la rinitis cr\u00f3nica\u00a0 comportan tal gravedad \u00a0 que hagan imprescindible el traslado a Bogot\u00e1; (ii) el accionante ingres\u00f3 a la \u00a0 carrera judicial luego de participar en la convocatoria n\u00famero 4528 de 2008 para \u00a0 el cargo de Magistrado de Sala \u00danica y no de Sala Penal; y (iii) la \u00a0 documentaci\u00f3n que el accionante alleg\u00f3 a la Unidad de Administraci\u00f3n de Carrera \u00a0 Judicial con el prop\u00f3sito de justificar el traslado se refiere a una enfermedad \u00a0 grave que padece su padre. \u00a0 \u00a0<\/p>\n<p>9.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Igualmente destac\u00f3 que la determinaci\u00f3n de la \u00a0 Corte Suprema de Justicia no genera un menoscabo cierto, claro y directo de los \u00a0 derechos fundamentales del accionante pues, de acuerdo con la informaci\u00f3n \u00a0 suministrada por el Instituto Nacional de Medicina Legal y Ciencias Forenses[10], as\u00ed como por las \u00a0 cl\u00ednicas Country y Santa Fe[11], \u00a0 no hay evidencia cient\u00edfica que demuestre con claridad que el traslado a un \u00a0 clima c\u00e1lido o fr\u00edo controle o disminuya tales enfermedades. De acuerdo con los \u00a0 expertos, estos padecimientos m\u00e9dicos pueden ser tratados con medicamentos y \u00a0 como medida de prevenci\u00f3n sugieren evitar el humo del cigarrillo y el aire \u00a0 contaminado, raz\u00f3n por la cual la ciudad de Bogot\u00e1 podr\u00eda agravar el nivel de \u00a0 salud del accionante por su alto nivel de poluci\u00f3n[12]. \u00a0 \u00a0<\/p>\n<p>Impugnaci\u00f3n \u00a0 \u00a0<\/p>\n<p>10.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El 21 de mayo de 2018, el accionante impugn\u00f3 la \u00a0 decisi\u00f3n de primera instancia. De manera preliminar se\u00f1al\u00f3 que, acorde con el \u00a0 Decreto 1983 de 2017, el asunto debi\u00f3 haberse sometido a reparto entre los \u00a0 jueces del circuito dado que no se cuestiona una decisi\u00f3n jurisdiccional, sino \u00a0 una decisi\u00f3n eminentemente administrativa. Por otra parte, afirm\u00f3 que el medio \u00a0 de control de nulidad y restablecimiento del derecho no es el mecanismo judicial \u00a0 id\u00f3neo para tramitar su pretensi\u00f3n, comoquiera que tendr\u00eda que permanecer de \u00a0 manera indefinida, hasta que se decida el medio de control, en el Tribunal \u00a0 Superior del Distrito Judicial de Yopal, vulnerando con ello el principio del \u00a0 m\u00e9rito, pues se prolongar\u00eda el cargo de provisionalidad en el Tribunal Superior \u00a0 del Distrito Judicial de Bogot\u00e1 \u2013 Sala Penal. \u00a0 \u00a0<\/p>\n<p>11.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Respecto del requisito de inmediatez de la acci\u00f3n \u00a0 de tutela, asegur\u00f3 que han transcurrido seis (6) meses desde la adopci\u00f3n de la \u00a0 decisi\u00f3n controvertida, pues solo hasta el 6 de diciembre de 2017 tuvo \u00a0 conocimiento de la respuesta negativa de la solicitud de traslado por razones de \u00a0 salud. De otro lado, se\u00f1al\u00f3 que la respuesta negativa a su solicitud de traslado \u00a0 se origin\u00f3 en las enfermedades que padece, al no ser consideradas por los \u00a0 magistrados de la Sala Plena de la Corte Suprema de Justicia como graves pese a \u00a0 que tal calificaci\u00f3n deb\u00eda realizarla un m\u00e9dico especializado. En consecuencia, \u00a0 aun cuando el m\u00e9dico tratante viene ejecutando un procedimiento terap\u00e9utico para \u00a0 mejorar los s\u00edntomas de las enfermedades que aquejan al se\u00f1or Vincos Urue\u00f1a, \u00a0 explic\u00f3 que se trata de una mejor\u00eda transitoria, ya que las condiciones \u00a0 clim\u00e1ticas del municipio de Yopal le obligan a estar expuesto al uso de \u00a0 ventiladores y aires acondicionados, los cuales debe evitar[13]. \u00a0 \u00a0<\/p>\n<p>Decisi\u00f3n de segunda instancia: Corte \u00a0 Suprema de Justicia \u2013 Sala de Casaci\u00f3n Civil[14] \u00a0 \u00a0<\/p>\n<p>12.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El 15 de noviembre de 2018, la Sala de Casaci\u00f3n \u00a0 Civil de la Corte Suprema de Justicia, integrada por conjueces, revoc\u00f3 la \u00a0 sentencia de tutela de primera instancia y, en su lugar, concedi\u00f3 el amparo de \u00a0 los derechos fundamentales al debido proceso y a la salud del accionante. De \u00a0 manera preliminar, se\u00f1al\u00f3 que el medio de control de nulidad y restablecimiento \u00a0 del derecho no es el medio judicial suficientemente eficaz frente al menoscabo \u00a0 de las garant\u00edas fundamentales invocadas, dado que la Jurisdicci\u00f3n de lo \u00a0 Contencioso Administrativo no tendr\u00e1 prontitud para proteger los derechos a la \u00a0 vida digna y a la integridad personal del funcionario judicial. Incluso, la \u00a0 medida cautelar de suspensi\u00f3n provisional del acto administrativo no ser\u00eda \u00a0 efectiva para evitar un perjuicio a la salud del servidor p\u00fablico, derivado de \u00a0 la permanencia en un entorno ambiental que altera sus condiciones de existencia \u00a0 digna. \u00a0 \u00a0<\/p>\n<p>13.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Posteriormente, precis\u00f3 que tanto el art\u00edculo 152 \u00a0 de la Ley Estatutaria de Administraci\u00f3n de Justicia, como el art\u00edculo 1\u00ba de la \u00a0 Ley 771 de 2002 aluden al traslado como una forma de provisi\u00f3n de cargos de \u00a0 carrera en la rama judicial y por tanto, su procedencia se encuentra limitada a \u00a0 que se presenten unos eventos, entre los cuales se advierte la reubicaci\u00f3n por \u00a0 razones de salud debidamente comprobadas que imposibilitan mantener la \u00a0 continuidad en el cargo. \u00a0 \u00a0<\/p>\n<p>14.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En este orden de ideas, destac\u00f3 que el Acuerdo \u00a0 No. PSAA10-6837 de 2010 expedido por la Sala Administrativa del Consejo Superior \u00a0 de la Judicatura establece que el servidor p\u00fablico que solicite el traslado, en \u00a0 oportunidad, por problemas de salud deber\u00e1 allegar un dictamen m\u00e9dico que \u00a0 refleje el diagn\u00f3stico de la patolog\u00eda y la recomendaci\u00f3n de traslado por \u00a0 imposibilidad de seguir desempe\u00f1ando el cargo expedido por la entidad promotora \u00a0 de salud o por la administradora de riesgos laborales a la que se encuentre \u00a0 afiliado. De manera que, a la Unidad de Administraci\u00f3n de la Carrera Judicial le \u00a0 compete emitir un concepto acerca de tal solicitud, el cual en caso de ser \u00a0 favorable es remitido a la autoridad nominadora (art\u00edculo 131 de la Ley \u00a0 Estatutaria de Administraci\u00f3n de Justicia) para que adopte una decisi\u00f3n con base \u00a0 en criterios objetivos, concretos y razonados. \u00a0 \u00a0<\/p>\n<p>15.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Con fundamento en los anteriores argumentos, \u00a0 sostuvo que la protecci\u00f3n del accionante resulta procedente toda vez que la \u00a0 entidad demandada quebrant\u00f3 sus garant\u00edas al debido proceso y al trabajo en \u00a0 condiciones dignas, pues la respuesta otorgada por el presidente de la Corte \u00a0 Suprema de Justicia a la petici\u00f3n elevada por el se\u00f1or Vincos Urue\u00f1a, cuatro \u00a0 meses despu\u00e9s de su remisi\u00f3n, carece de suficiente motivaci\u00f3n dado que no \u00a0 relacion\u00f3 ninguna explicaci\u00f3n sobre los criterios objetivos y razonados que \u00a0 fundaron la negativa del traslado, sino que se limit\u00f3 decidir conforme con la \u00a0 facultad que le asiste como autoridad nominadora. \u00a0 \u00a0<\/p>\n<p>16.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Adicionalmente, aclar\u00f3 que la Sala Plena de la \u00a0 Corte Suprema de Justicia no tiene la facultad para avalar o cuestionar la \u00a0 idoneidad del diagn\u00f3stico emitido por el m\u00e9dico tratante del solicitante, tal y \u00a0 como lo se\u00f1al\u00f3 esa corporaci\u00f3n en la providencia STC2744 \u2013 2018 del 28 de \u00a0 febrero de 2018. Indic\u00f3 que no existe ning\u00fan impedimento para que el accionante, \u00a0 como Magistrado de la Sala \u00danica del Tribunal Superior del Distrito Judicial de \u00a0 Yopal pueda ejercer el cargo de Magistrado de una Sala Especializada de \u00a0 Tribunal, ya que existe afinidad de funciones entre esos dos cargos; de hecho, \u00a0 precis\u00f3 que tambi\u00e9n se vulner\u00f3 el derecho a la igualdad del se\u00f1or Vincos Urue\u00f1a \u00a0 respecto de otros servidores judiciales que como \u00e9l, ocupaban en propiedad el \u00a0 cargo de magistrado de Sala \u00danica de Tribunal y que les fue concedido el \u00a0 traslado que solicitaron para cargos de magistrados de Salas Especializadas de \u00a0 Tribunal. En consecuencia, estim\u00f3 que la nominadora fund\u00f3 su negativa al \u00a0 traslado requerido por razones subjetivas y sobre aspectos ajenos a los que \u00a0 deb\u00edan ser objeto de an\u00e1lisis y valoraci\u00f3n, en la medida que tampoco ponder\u00f3 las \u00a0 aptitudes de m\u00e9rito e idoneidad profesional del demandante. Finalmente, destac\u00f3 \u00a0 que tanto la salud del accionante como la de su progenitor, quien es un sujeto \u00a0 de especial protecci\u00f3n constitucional por su edad, se encuentran en riesgo y que \u00a0 en raz\u00f3n de ello, la sentencia de tutela de primera instancia debi\u00f3 tener un \u00a0 enfoque diferencial bajo consideraciones humanitarias[15]. \u00a0 \u00a0<\/p>\n<p>D.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0ACTUACIONES ADELANTADAS ANTE LA CORTE \u00a0 CONSTITUCIONAL Y PRUEBAS RECAUDADAS EN SEDE DE REVISI\u00d3N \u00a0 \u00a0<\/p>\n<p>17.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En desarrollo del \u00a0 tr\u00e1mite de revisi\u00f3n, el magistrado sustanciador con fundamento en el art\u00edculo 64 \u00a0 del Acuerdo 02 de 2015 \u201cPor medio del cual se unifica \u00a0 y actualiza el Reglamento de la Corte Constitucional\u201d, consider\u00f3 necesario disponer de mayores \u00a0 elementos de juicio que le permitieran esclarecer la situaci\u00f3n f\u00e1ctica del \u00a0 asunto sometido a estudio. Para ello orden\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cPRIMERO.- Por Secretar\u00eda General de esta Corte, OF\u00cdCIESE al se\u00f1or \u00c1lvaro \u00a0 Vincos Urue\u00f1a, para que dentro del t\u00e9rmino de cuarenta y ocho (48) horas \u00a0 siguientes al recibo de la notificaci\u00f3n de esta providencia informe al despacho \u00a0 su lugar de vinculaci\u00f3n laboral actual. En caso de encontrarse ejerciendo el \u00a0 cargo de Magistrado del Tribunal Superior del Distrito Judicial de Bogot\u00e1 \u2013 Sala \u00a0 Penal, es necesario que aporte los documentos de nombramiento y posesi\u00f3n de tal \u00a0 cargo. \u00a0 \u00a0<\/p>\n<p>SEGUNDO.- Por \u00a0 Secretar\u00eda General de esta Corte, OF\u00cdCIESE a la Sala Administrativa del Consejo \u00a0 Superior de la Judicatura ubicada en la calle 12 No. 7 \u2013 65 para que dentro del \u00a0 t\u00e9rmino de cuarenta y ocho (48) horas siguientes al recibo de la notificaci\u00f3n de \u00a0 esta providencia informe al despacho si: \u00a0 \u00a0<\/p>\n<p>(i)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Para el momento en que el se\u00f1or \u00c1lvaro \u00a0 Vincos Urue\u00f1a present\u00f3 la tutela de la referencia o durante el transcurso de \u00a0 \u00e9sta, existi\u00f3 una lista de elegibles para suplir las vacantes de la Sala Penal \u00a0 del Tribunal Superior del Distrito Judicial de Bogot\u00e1. \u00a0 \u00a0<\/p>\n<p>(i)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Son equiparables las pruebas del concurso \u00a0 de m\u00e9rito que se realizan para cubrir las vacantes de Magistrado Tribunal de \u00a0 Sala \u00danica y Magistrado de Tribunal de Sala Especializada. En caso de ser \u00a0 afirmativa la respuesta, es necesario explicar la raz\u00f3n por la cual se hacen \u00a0 concursos de m\u00e9ritos distintos para proveer dichos cargos. \u00a0 \u00a0<\/p>\n<p>(ii)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Son equiparables las funciones de \u00a0 Magistrado de Tribunal de Sala \u00danica y Magistrado de Tribunal de Sala \u00a0 Especializada. \u00a0 \u00a0<\/p>\n<p>TERCERO.- Por \u00a0 Secretar\u00eda General de esta Corte, OF\u00cdCIESE a la Unidad de Administraci\u00f3n de \u00a0 Carrera Judicial ubicada en Carrera 8 N\u00b012B-82 (Edificio de la Bolsa) y a la \u00a0 direcci\u00f3n electr\u00f3nica: \u00a0 carjud@cendoj.ramajudicial.gov.co \u00a0para que dentro del t\u00e9rmino de cuarenta y ocho (48) horas siguientes al recibo \u00a0 de la notificaci\u00f3n de esta providencia informe al despacho si: \u00a0 \u00a0<\/p>\n<p>(ii)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Son equiparables las pruebas del concurso \u00a0 de m\u00e9rito que se realizan para cubrir las vacantes de Magistrado Tribunal de \u00a0 Sala \u00danica y Magistrado de Tribunal de Sala Especializada. En caso de ser \u00a0 afirmativa la respuesta, es necesario explicar la raz\u00f3n por la cual se hacen \u00a0 concursos de m\u00e9ritos distintos para proveer dichos cargos. \u00a0 \u00a0<\/p>\n<p>(iii)\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Son equiparables las funciones de \u00a0 Magistrado de Tribunal de Sala \u00danica y Magistrado de Tribunal de Sala \u00a0 Especializada\u201d[16]. \u00a0 \u00a0<\/p>\n<p>\u201cPRIMERO.- Por Secretar\u00eda General de esta Corte, OF\u00cdCIESE a la Secretar\u00eda \u00a0 General de la Corte Suprema de Justicia, ubicada en la calle 12 No.\u00a0 7 \u2013 \u00a0 65, para que dentro del t\u00e9rmino de cuarenta y ocho (48) horas siguientes al \u00a0 recibo de la notificaci\u00f3n de esta providencia informe al despacho si la vacante \u00a0 de magistrado del Tribunal Superior del Distrito Judicial de Yopal \u2013 Sala \u00danica, \u00a0 que antes era ocupada por el se\u00f1or \u00c1lvaro Vincos Urue\u00f1a, actualmente se \u00a0 encuentra ocupada. En caso de ser afirmativa la respuesta, informe la fecha de \u00a0 la elecci\u00f3n y\u00a0 el tipo de vinculaci\u00f3n que ostenta la persona que ocupa \u00a0 dicho cargo (provisionalidad o propiedad), adem\u00e1s del acta de posesi\u00f3n. \u00a0 \u00a0<\/p>\n<p>SEGUNDO.- Por \u00a0 Secretar\u00eda General de esta Corte, OF\u00cdCIESE a la Sala Administrativa del Consejo \u00a0 Superior de la Judicatura ubicada en la calle 12 No.\u00a0 7 \u2013 65 para que \u00a0 dentro del t\u00e9rmino de cuarenta y ocho (48) horas siguientes al recibo de la \u00a0 notificaci\u00f3n de esta providencia informe al despacho si: \u00a0 \u00a0<\/p>\n<p>(i)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Si existe una lista de elegibles para \u00a0 suplir la vacante de la Sala \u00danica del Tribunal Superior del Distrito Judicial \u00a0 de Yopal. \u00a0 \u00a0<\/p>\n<p>(iv)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0Si existe, adem\u00e1s del cargo del se\u00f1or \u00a0 \u00c1lvaro Vincos Urue\u00f1a, otra vacante en la Sala \u00danica del Tribunal Superior del \u00a0 Distrito Judicial de Yopal\u201d[17]. \u00a0 \u00a0<\/p>\n<p>18.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En respuesta de las \u00a0 pruebas solicitadas[18], \u00a0 se obtuvo la siguiente informaci\u00f3n: \u00a0 \u00a0<\/p>\n<p>&#8211; El 22 de abril de \u00a0 2019, el se\u00f1or \u00c1lvaro Vincos Urue\u00f1a inform\u00f3 que el 1\u00b0 de febrero del a\u00f1o en \u00a0 curso tom\u00f3 posesi\u00f3n en el cargo de Magistrado de la Sala Penal del Tribunal \u00a0 Superior del Distrito Judicial de Bogot\u00e1, de acuerdo con el traslado en \u00a0 propiedad que se decidi\u00f3 en sesi\u00f3n ordinaria de la Sala Plena de la Corte \u00a0 Suprema de Justicia, el pasado 29 de noviembre de 2018[19]. \u00a0 \u00a0<\/p>\n<p>&#8211; El 23 de abril de \u00a0 2019, la Unidad de Administraci\u00f3n de Carrera Judicial se\u00f1al\u00f3 que, estando en \u00a0 curso la segunda instancia de la acci\u00f3n de la referencia, el 1\u00b0 de octubre de \u00a0 2018 fue publicada la vacante del cargo de Magistrado de Sala Penal del Tribunal \u00a0 Superior del Distrito Judicial de Bogot\u00e1 dejada por el doctor Orlando Mu\u00f1oz \u00a0 Ortiz, raz\u00f3n por la cual, mediante Acuerdo PCSJA18-11152 del 15 de noviembre de \u00a0 2018, el Consejo Superior de la Judicatura formul\u00f3 ante la Corte Suprema de \u00a0 Justicia la lista de candidatos, de conformidad con la relaci\u00f3n de aspirantes \u00a0 del registro de elegibles que optaron por esa sede, en virtud del concurso \u00a0 adelantado mediante Acuerdo PSAA13-9939 de 2013 cuya vigencia inici\u00f3 el 10 de \u00a0 julio de 2018. \u00a0 \u00a0<\/p>\n<p>De otro lado, \u00a0 precis\u00f3 que no son equiparables las pruebas del concurso de m\u00e9rito que se \u00a0 realizan para cubrir las vacantes de Magistrado de Sala \u00danica de Tribunal y las \u00a0 de Magistrado de Sala Especializada de Tribunal, pues los cargos corresponden a \u00a0 diferente especialidad, as\u00ed como los asuntos y temas de estudio que en \u00a0 desarrollo de sus funciones deben atender. La estructura de las pruebas para \u00a0 estos cargos es diferente, toda vez que el Consejo Superior de la Judicatura, al \u00a0 adelantar los distintos procesos de selecci\u00f3n, fija el contenido, alcance y \u00a0 aspectos de cada una de las etapas del proceso concursal de conformidad con el \u00a0 perfil y funciones de cada cargo. \u00a0 \u00a0<\/p>\n<p>Asimismo, destac\u00f3 \u00a0 que el curso de formaci\u00f3n judicial de la Convocatoria 22, impartido por la \u00a0 Escuela Judicial Rodrigo Lara Bonilla, comprend\u00eda dos partes,\u00a0 una de \u00a0 formaci\u00f3n general dirigida a todos los aspirantes, integrada por ejes tem\u00e1ticos \u00a0 transversales a todas las etapas, y otra de formaci\u00f3n especializada dirigida a \u00a0 los aspirantes en ejes tem\u00e1ticos espec\u00edficos acorde con la especialidad del \u00a0 cargo. De manera que, para efectos de impartir el curso de formaci\u00f3n, los \u00a0 docentes fueron divididos en grupos, correspondiendo a distinto grupo el de \u00a0 magistrado de la Sala Penal del Tribunal Superior y el de magistrado de la Sala \u00a0 \u00danica del Tribunal Superior. \u00a0 \u00a0<\/p>\n<p>Finalmente, aclar\u00f3 \u00a0 que los Tribunales Superiores, de conformidad con lo dispuesto en el art\u00edculo 19 \u00a0 de la Ley 270 de 1996, son creados por el Consejo Superior de la Judicatura para \u00a0 el cumplimiento de las funciones que determine la ley procesal en cada distrito \u00a0 judicial. En consecuencia, las funciones de magistrado de Sala \u00danica de Tribunal \u00a0 son diferentes a las funciones de magistrado de Sala Especializada de Tribunal, \u00a0 ya que los primeros conocen indistintamente de toda clase de procesos sin \u00a0 atender al criterio de especializaci\u00f3n, contrario a lo que ocurre en las salas \u00a0 especializadas que, para el caso de las salas penales, es el C\u00f3digo de \u00a0 Procedimiento Penal el que determina en los art\u00edculos 33 y 34 los asuntos que \u00a0 conocen[20]. \u00a0 \u00a0<\/p>\n<p>&#8211; El 2 de mayo de \u00a0 2019, el se\u00f1or \u00c1lvaro Vincos Urue\u00f1a precis\u00f3 que para la fecha de presentaci\u00f3n, \u00a0 admisi\u00f3n y fallo de primera instancia de la tutela de la referencia no exist\u00eda \u00a0 registro de elegibles para el cargo de Magistrado de la Sala Penal del Tribunal \u00a0 Superior del Distrito Judicial de Bogot\u00e1, sino que la misma fue expedida al \u00a0 momento del fallo de segunda instancia. Por tanto, dicha prueba no fue conocida \u00a0 ni introducida en el proceso que se revisa. \u00a0 \u00a0<\/p>\n<p>De otro lado, \u00a0 explic\u00f3 que las pruebas de los concursos de m\u00e9rito de magistrado de Sala \u00a0 Especializada de Tribunal Superior del Distrito Judicial y magistrado de Sala \u00a0 \u00danica de Tribunal Superior del Distrito Judicial son equiparables, pues basta \u00a0 con mirar el cuadro remitido por la Secretar\u00eda de la Unidad de Administraci\u00f3n de \u00a0 Carrera Judicial (folio 54 cuaderno principal) sobre los temas a presentar en \u00a0 las pruebas del componente o especialidad penal, para afirmar que son los \u00a0 mismos. La diferencia, afirma, radica en que el cargo de magistrado de Sala \u00a0 \u00danica de Tribunal, adem\u00e1s del componente espec\u00edfico penal debe presentar y pasar \u00a0 conocimientos espec\u00edficos en laboral y civil, lo que supone una mayor carga que \u00a0 no puede interpretarse en su contra. \u00a0 \u00a0<\/p>\n<p>Por \u00faltimo, destac\u00f3 \u00a0 que las funciones de los magistrados de Sala Especializada y las de Sala \u00danica \u00a0 de Tribunal son equiparables en el componente espec\u00edfico, que para este caso es \u00a0 materia penal, de acuerdo con los art\u00edculos 33 y 34 de la Ley 906 de 2004, el \u00a0 C\u00f3digo de Procedimiento Penal, la Ley 600 de 2000 y la Ley 1098 de 2006. De ah\u00ed \u00a0 que lo \u00fanico diferente es la denominaci\u00f3n del cargo[21]. \u00a0 \u00a0<\/p>\n<p>&#8211; El 2 de mayo de \u00a0 2019, el Presidente de la Corte Suprema de Justicia, Doctor \u00c1lvaro Fernando \u00a0 Garc\u00eda Restrepo, indic\u00f3 que para el momento en que la Sala Plena acat\u00f3 el fallo \u00a0 de segunda instancia de tutela, esto es, el 29 de noviembre de 2018, exist\u00eda una \u00a0 lista de elegibles vigente para el cargo de Magistrado de la Sala Penal del \u00a0 Tribunal Superior del Distrito Judicial, la cual se materializ\u00f3 en el Acuerdo \u00a0 PCSJA18-11152 del 15 de noviembre de 2018 del Consejo Superior de la Judicatura. \u00a0 \u00a0<\/p>\n<p>Igualmente, se\u00f1al\u00f3 \u00a0 que conforme con lo aclarado sobre las pruebas para los cargos de magistrado de \u00a0 Sala Especializada y Sala \u00danica de Tribunal, en el presente asunto no hab\u00eda \u00a0 lugar a conceder el traslado solicitado por \u00c1lvaro Vincos Urue\u00f1a. Por \u00a0 consiguiente, solicit\u00f3 a la Sala Cuarta de Revisi\u00f3n de la Corte Constitucional \u00a0 revocar la decisi\u00f3n de tutela proferida por la Sala de Casaci\u00f3n de la Corte \u00a0 Suprema de Justicia[22]. \u00a0 \u00a0<\/p>\n<p>&#8211; El 7 de mayo de \u00a0 2019, la Secretar\u00eda General de la Corte Suprema de Justicia inform\u00f3 que la \u00a0 vacante de magistrado de la Sala \u00danica del Tribunal Superior del Distrito \u00a0 Judicial de Yopal se encuentra ocupada por Mar\u00eda Stella Jara Guti\u00e9rrez, quien \u00a0 fue nombrada en encargo\/provisionalidad en sesi\u00f3n extraordinaria de la Sala \u00a0 Plena de la Corte Suprema de Justicia el 12 de marzo de 2019[23]. \u00a0 \u00a0<\/p>\n<p>II.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0CONSIDERACIONES \u00a0 \u00a0<\/p>\n<p>A.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0COMPETENCIA \u00a0 \u00a0<\/p>\n<p>19.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Esta Corte es competente para conocer de la \u00a0 acci\u00f3n de tutela de la referencia, de conformidad con lo establecido en los \u00a0 art\u00edculos 86 y 241 numeral 9 de la Constituci\u00f3n Pol\u00edtica, en los art\u00edculos 31 a \u00a0 36 del Decreto 2591 de 1991, y en virtud del Auto proferido el 28 de enero de \u00a0 2019, por la Sala de Selecci\u00f3n de Tutelas N\u00famero Uno de esta Corporaci\u00f3n, que decidi\u00f3 seleccionar para revisi\u00f3n el proceso de la referencia. \u00a0 \u00a0<\/p>\n<p>B.\u00a0\u00a0\u00a0\u00a0 \u00a0CUESTIONES PREVIAS \u2013 PROCEDIBILIDAD DE LA \u00a0 ACCI\u00d3N DE TUTELA \u00a0 \u00a0<\/p>\n<p>20.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En virtud de lo dispuesto en el art\u00edculo 86 de la \u00a0 Constituci\u00f3n Pol\u00edtica, la reiterada jurisprudencia constitucional dictada en la \u00a0 materia[24] \u00a0y los art\u00edculos concordantes del Decreto 2591 de 1991, la acci\u00f3n de tutela tiene \u00a0 un car\u00e1cter residual y subsidiario, raz\u00f3n por la cual solo procede \u00a0 excepcionalmente como mecanismo de protecci\u00f3n definitivo (i) cuando el \u00a0 presunto afectado no disponga de otro medio de defensa judicial, o (ii) cuando \u00a0 existiendo, ese medio carece de idoneidad o eficacia para proteger de forma \u00a0 adecuada, oportuna e integral los derechos fundamentales, en las circunstancias \u00a0 del caso concreto. As\u00ed mismo, proceder\u00e1 como mecanismo transitorio \u00a0cuando se interponga para evitar la consumaci\u00f3n de un perjuicio irremediable a \u00a0 un derecho fundamental. En el evento de proceder como mecanismo transitorio, el \u00a0 accionante deber\u00e1 ejercer dicha acci\u00f3n en un t\u00e9rmino m\u00e1ximo de cuatro (4) meses \u00a0 a partir del fallo de tutela y la protecci\u00f3n se extender\u00e1 hasta tanto se \u00a0 produzca una decisi\u00f3n definitiva por parte del juez ordinario[25]. \u00a0 \u00a0<\/p>\n<p>21.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Antes de realizar el estudio de fondo de la \u00a0 acci\u00f3n de tutela seleccionada, la Sala proceder\u00e1 primero a verificar si esta \u00a0 cumple los requisitos formales de procedibilidad. \u00a0 \u00a0<\/p>\n<p>Procedencia de la acci\u00f3n de tutela \u2013 Caso \u00a0 concreto \u00a0 \u00a0<\/p>\n<p>22.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Legitimaci\u00f3n por activa: El art\u00edculo 86 de la Constituci\u00f3n ha previsto que cualquier persona \u00a0 tendr\u00e1 acci\u00f3n de tutela para reclamar ante los jueces la protecci\u00f3n de los \u00a0 derechos fundamentales cuando estos resulten amenazados o vulnerados. El se\u00f1or \u00c1lvaro Vincos Urue\u00f1a, personalmente, como titular de los derechos fundamentales invocados interpuso la \u00a0 solicitud de amparo de la referencia, raz\u00f3n por la cual se encuentra acreditada la legitimidad para promover la misma (C.P. \u00a0 art. 86\u00ba, Decreto 2591\/91 art. 1\u00ba y art.10\u00b0). \u00a0 \u00a0<\/p>\n<p>23.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Legitimaci\u00f3n por pasiva: El art\u00edculo 86 superior prev\u00e9 que la acci\u00f3n \u00a0 de tutela es procedente frente a particulares cuando: (a) estos se encuentran \u00a0 encargados de la prestaci\u00f3n de un servicio p\u00fablico; (b) la conducta del \u00a0 particular afecta grave y directamente el inter\u00e9s colectivo; o (c) el \u00a0 solicitante se halle en estado de subordinaci\u00f3n o indefensi\u00f3n frente al \u00a0 particular[26]. A su vez, el art\u00edculo 5\u00ba del Decreto 2591 de 1991 establece que la \u00a0 acci\u00f3n de tutela procede contra toda acci\u00f3n u omisi\u00f3n de una autoridad p\u00fablica \u00a0 que haya violado, viole o amenace un derecho fundamental. La demanda de tutela fue promovida en contra de la Corte Suprema de \u00a0 Justicia \u2013 Sala Plena, entidad p\u00fablica a la que se le atribuye la presunta \u00a0 vulneraci\u00f3n de los derechos fundamentales del accionante. Por tanto, la Sala \u00a0 entiende acreditado el requisito de legitimaci\u00f3n por pasiva. \u00a0 \u00a0<\/p>\n<p>24.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Inmediatez: \u00a0Este requisito de procedibilidad impone la carga al demandante de \u00a0 interponer la acci\u00f3n de tutela en un t\u00e9rmino prudente y razonable respecto del \u00a0 hecho o la conducta que causa la vulneraci\u00f3n de derechos fundamentales. Conforme \u00a0 a lo anterior, la Corte ha dispuesto que se debe presentar la solicitud de \u00a0 amparo dentro de un plazo razonable, el cual debe ser analizado caso por caso[27]. \u00a0 \u00a0<\/p>\n<p>Los hechos que dieron origen a \u00a0 la presunta vulneraci\u00f3n de los derechos fundamentales alegados por el accionante \u00a0 ocurrieron el 6 de diciembre de 2017, d\u00eda en el que la Presidencia de la Corte \u00a0 Suprema de Justicia le comunic\u00f3 que, mediante plenaria celebrada el 28 de \u00a0 septiembre de ese a\u00f1o, su solicitud de traslado le fue negada, toda vez que no \u00a0 obtuvo los votos m\u00ednimos requeridos para su aprobaci\u00f3n. Por consiguiente, dado \u00a0 que la fecha de interposici\u00f3n de la presente acci\u00f3n fue el 3 de abril de 2018, \u00a0 es decir, a los tres (3) meses y veintisiete (27) d\u00edas de haberse generado la \u00a0 presunta vulneraci\u00f3n de los derechos fundamentales alegados por el actor, es un \u00a0 t\u00e9rmino que la Sala encuentra prudente y razonable para reclamar su protecci\u00f3n. \u00a0 \u00a0<\/p>\n<p>25.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Subsidiariedad: El \u00a0 art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica de 1991 establece que la acci\u00f3n de \u00a0 tutela s\u00f3lo proceder\u00e1 cuando el afectado no disponga de otro medio de defensa \u00a0 judicial, salvo en los casos en que sea interpuesta como mecanismo transitorio \u00a0 para evitar la configuraci\u00f3n de un perjuicio irremediable. De igual forma, se ha \u00a0 aceptado la procedencia definitiva del amparo de tutela en aquellas situaciones \u00a0 en las que, existiendo recursos judiciales, los mismos no sean id\u00f3neos o \u00a0 eficaces para evitar la vulneraci\u00f3n del derecho constitucional fundamental. \u00a0 \u00a0<\/p>\n<p>26.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0La jurisprudencia de la Corte Constitucional ha \u00a0 establecido, por regla general, que no procede la acci\u00f3n de tutela en contra de \u00a0 los actos administrativos de car\u00e1cter particular y concreto, pues el debate en \u00a0 torno a su legalidad con ocasi\u00f3n de su aplicaci\u00f3n o interpretaci\u00f3n corresponde a \u00a0 la Jurisdicci\u00f3n de lo Contencioso Administrativo. No obstante, trat\u00e1ndose de \u00a0 actos administrativos de car\u00e1cter particular y concreto que presuntamente \u00a0 lesionan los derechos de la carrera judicial, este Tribunal ha aceptado la \u00a0 procedencia excepcional de la acci\u00f3n de tutela como mecanismo definitivo, a fin \u00a0 de salvaguardar el principio del m\u00e9rito, toda vez que \u201ces el \u00fanico criterio que debe regir el ingreso, la permanencia \u00a0 y el ascenso en la carrera judicial\u201d[28]. \u00a0 \u00a0<\/p>\n<p>27.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0As\u00ed, mediante sentencia T-488 de 2004, la Sala \u00a0 Sexta de Revisi\u00f3n de la Corporaci\u00f3n resolvi\u00f3 el caso de un se\u00f1or que ocup\u00f3 el \u00a0 primer puesto de la lista de elegibles para el cargo de Juez Promiscuo Municipal \u00a0 y no fue nombrado en dicha vacante, toda vez que la entidad nominadora acept\u00f3 el \u00a0 traslado de otro funcionario p\u00fablico a ese cargo. En dicha oportunidad, la Corte \u00a0 se\u00f1al\u00f3 que la acci\u00f3n de tutela procede en contra de los actos administrativos \u00a0 que provean vacantes dentro de la carrera judicial, pese a la existencia del \u00a0 medio de control de nulidad y restablecimiento del derecho, a fin de evitar un \u00a0 perjuicio injustificado para quien s\u00ed le asiste el derecho a ser nombrado. Sobre \u00a0 el particular manifest\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cEn suma, el acto administrativo mediante el cual una persona es \u00a0 nombrada en un cargo para el cual no tiene derecho, sea cual sea el sistema que \u00a0 se haya empleado para proveer la vacante (listado de elegibles, traslado o los \u00a0 dos), puede ser impugnado mediante el ejercicio de la acci\u00f3n de tutela para \u00a0 evitar el perjuicio que representar\u00eda, para quien s\u00ed asiste el derecho, el ser \u00a0 privado injustificadamente del nombramiento por el tiempo que tarda el \u00a0 agotamiento de las acciones contencioso administrativas ordinarias\u201d. \u00a0 \u00a0<\/p>\n<p>28.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En el mismo sentido, la \u00a0 Sala Primera de Revisi\u00f3n de este Tribunal, en sentencia T- 159 de 2017, analiz\u00f3 \u00a0 el caso de una funcionaria judicial a quien le negaron su solicitud de traslado \u00a0 por razones de salud, del Tribunal Administrativo de Bol\u00edvar al Tribunal \u00a0 Administrativo de Santander, por presentarse tal petici\u00f3n fuera del t\u00e9rmino \u00a0 previsto para ello. En esa ocasi\u00f3n, la Corte consider\u00f3 que aun cuando la \u00a0 decisi\u00f3n que se cuestionaba pod\u00eda recurrirse ante la Jurisdicci\u00f3n de lo \u00a0 Contencioso Administrativo y solicitar las medidas cautelares pertinentes para \u00a0 el efecto, la acci\u00f3n de tutela era el mecanismo judicial procedente para dejar \u00a0 sin efectos los actos administrativos que presuntamente lesionan derechos de \u00a0 carrera. Al respecto se precis\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cSi bien la accionante pudo acudir a la jurisdicci\u00f3n contencioso \u00a0 administrativa en procura de perseguir la nulidad de los actos administrativos a \u00a0 los que les atribuye la vulneraci\u00f3n de sus derechos fundamentales, adem\u00e1s del \u00a0 restablecimiento de los mismos, y solicitar las medidas cautelares pertinentes \u00a0 para proteger y garantizar, provisionalmente, el objeto del proceso y la \u00a0 efectividad de la sentencia, conforme a los art\u00edculos 229 y 230 de la Ley 1437 \u00a0 de 2011, la Corte ha aceptado que se acuda al mecanismo del amparo \u00a0 constitucional cuando se pretende dejar sin efectos actos administrativos que \u00a0 presuntamente lesionan derechos de carrera, como puede ocurrir en el presente \u00a0 caso con el derecho al traslado de un servidor judicial por razones de salud. \u00a0 Adem\u00e1s, ha estimado que la acci\u00f3n de tutela proporciona una soluci\u00f3n m\u00e1s \u00a0 integral, m\u00e1xime cuando est\u00e1 en entredicho el derecho a la salud de quien acude \u00a0 a ella, por lo que se constituye en el mecanismo id\u00f3neo y eficaz para dar una \u00a0 protecci\u00f3n inmediata y definitiva\u201d (negrilla fuera del texto). \u00a0 \u00a0<\/p>\n<p>29.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Conforme con lo expuesto \u00a0 en precedencia, procede de manera excepcional la acci\u00f3n de tutela contra actos \u00a0 administrativos que decidan el traslado de funcionarios judiciales por razones \u00a0 de salud, aun cuando los mismos podr\u00edan recurrirse a trav\u00e9s del medio de control \u00a0 de nulidad y restablecimiento del derecho y \u00a0ser objeto de las medidas \u00a0 cautelares previstas en los art\u00edculos 229 y 230 del C\u00f3digo de Procedimiento \u00a0 Administrativo y de lo Contencioso Administrativo, en caso que el juez de tutela \u00a0 advierta que dicho acto presuntamente est\u00e1 afectando los derechos que se derivan \u00a0 de la carrera judicial. \u00a0 \u00a0<\/p>\n<p>Sin embargo, la Corte Constitucional tambi\u00e9n ha sostenido que cuando se discuten actos administrativos en \u00a0 el marco de un concurso de m\u00e9ritos, procede excepcionalmente la acci\u00f3n de tutela \u00a0 como mecanismo definitivo, cuando se controvierten actos de tr\u00e1mite o de \u00a0 ejecuci\u00f3n que vulneren de forma clara, grave y directa derechos fundamentales \u00a0 del actor o su n\u00facleo fundamental[32]. \u00a0 \u00a0<\/p>\n<p>31.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En este orden de ideas, \u00a0 esta Sala considera que la tutela de la referencia cumple con el requisito de \u00a0 procedibilidad toda vez que el demandante est\u00e1 cuestionando el acto \u00a0 administrativo por medio del cual la Sala Plena de la Corte Suprema de Justicia, \u00a0 en calidad de ente nominador, neg\u00f3 el traslado por razones de salud de la Sala \u00a0 \u00danica del Tribunal Superior del Distrito Judicial de Yopal a la Sala Penal del \u00a0 Tribunal Superior del Distrito Judicial de Bogot\u00e1, y en su lugar, prefiri\u00f3 \u00a0 mantener en dicha vacante a un funcionario en provisionalidad, afectando con tal \u00a0 decisi\u00f3n, presuntamente, los derechos que se derivan de la carrera judicial. \u00a0 Adem\u00e1s dicha decisi\u00f3n afect\u00f3, presuntamente, el derecho fundamental a la salud \u00a0 del se\u00f1or Vincos Urue\u00f1a al no permitir, en atenci\u00f3n a su padecimiento m\u00e9dico, el \u00a0 traslado a una ciudad de clima fr\u00edo como Bogot\u00e1, pese a la recomendaci\u00f3n emitida \u00a0 por su m\u00e9dico tratante. \u00a0 \u00a0<\/p>\n<p>C.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0PLANTEAMIENTO DEL PROBLEMA JUR\u00cdDICO, \u00a0 M\u00c9TODO Y ESTRUCTURA DE LA DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>32.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Acorde con los fundamentos f\u00e1cticos se\u00f1alados en \u00a0 la Secci\u00f3n I anterior de esta providencia, le corresponde a la Sala Cuarta de \u00a0 Revisi\u00f3n determinar si la Sala Plena de la Corte Suprema de Justicia, en calidad \u00a0 de ente nominador, vulner\u00f3 los derechos fundamentales al debido proceso \u00a0 administrativo, a la igualdad, a la salud y al trabajo en condiciones dignas del \u00a0 se\u00f1or \u00c1lvaro Vincos Urue\u00f1a al negarle el traslado por razones de salud que \u00a0 solicit\u00f3 para el cargo vacante de magistrado de la Sala Penal del Tribunal \u00a0 Superior del Distrito Judicial de Bogot\u00e1, pese a que (a) contaba con una \u00a0 recomendaci\u00f3n m\u00e9dica; y (b) con el concepto favorable de la Unidad de \u00a0 Administraci\u00f3n de Carrera Judicial. \u00a0 \u00a0<\/p>\n<p>33.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Con el fin de resolver el problema jur\u00eddico \u00a0 planteado, la Sala se referir\u00e1 al r\u00e9gimen legal y jurisprudencial de los \u00a0 traslados por razones de salud en la Rama Judicial (secci\u00f3n D) y sobre la base \u00a0 de este an\u00e1lisis, resolver\u00e1 el caso concreto sometido a \u00a0 estudio (Secci\u00f3n E). \u00a0 \u00a0<\/p>\n<p>D.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0R\u00c9GIMEN LEGAL Y \u00a0 JURISPRUDENCIA DE LOS TRASLADOS POR RAZONES DE SALUD EN LA RAMA JUDICIAL \u00a0 \u00a0<\/p>\n<p>34.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El art\u00edculo 29 de la \u00a0 Constituci\u00f3n consagra la protecci\u00f3n del debido proceso y dispone que este \u00a0 derecho consiste \u201cen \u00a0 el respeto a las formas previamente definidas, en punto de las actuaciones que \u00a0 se surtan en el \u00e1mbito administrativo y judicial, salvaguardando en todas sus \u00a0 etapas los principios de contradicci\u00f3n e imparcialidad\u201d. Este derecho \u00a0 ha sido concebido por la jurisprudencia constitucional como una reuni\u00f3n de \u00a0 etapas establecidas por la ley, que tienen como finalidad que las autoridades \u00a0 administrativas las cumplan y, a su vez, brinden a los administrados seguridad \u00a0 jur\u00eddica, as\u00ed como el correcto funcionamiento de la administraci\u00f3n y la certeza \u00a0 de la validez de sus actuaciones[33]. \u00a0 \u00a0<\/p>\n<p>35.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Acorde con el art\u00edculo \u00a0 134 de la Ley 270 de 1996, Ley Estatutaria de la Administraci\u00f3n de Justicia, \u00a0 modificado por el art\u00edculo 1 de la Ley 771 de 2002, \u201cSe produce traslado \u00a0 cuando se provee un cargo con un funcionario o empleado que ocupa en propiedad \u00a0 otro de funciones afines, de la misma categor\u00eda y para el cual se exijan los \u00a0 mismos requisitos, aunque tengan distinta sede territorial\u201d y \u00a0 procede, entre otras razones, seg\u00fan el numeral 1 de tal art\u00edculo, cuando el \u00a0 interesado lo solicite por razones de salud debidamente comprobadas, que le \u00a0 hagan imposible continuar en el cargo o por estas mismas razones se encuentre \u00a0 afectado o afectada su c\u00f3nyuge, compa\u00f1era o compa\u00f1ero permanente, descendiente o \u00a0 ascendiente en primer grado de consanguinidad o \u00fanico civil, siempre que ello no \u00a0 implique condiciones menos favorables para el funcionario y medie su \u00a0 consentimiento expreso[34]. \u00a0 En desarrollo de lo anterior, la Sala Administrativa del Consejo Superior de la \u00a0 Judicatura emiti\u00f3 el Acuerdo PSAA10-6837 de 2010[35], \u00a0 mediante el cual se reglament\u00f3 el r\u00e9gimen de traslados de los servidores \u00a0 judiciales. \u00a0 \u00a0<\/p>\n<p>36.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Posteriormente, la Presidencia del Consejo \u00a0 Superior de la Judicatura el 18 de septiembre de 2017 emiti\u00f3 el Acuerdo \u00a0 PCSJA17-10754 \u201cPor el cual se compilan los reglamentos de traslados de los \u00a0 servidores judiciales y se dictan otras disposiciones en la materia\u201d el cual \u00a0 reproduce de manera id\u00e9ntica lo atinente a los \u00a0 traslados de los servidores judiciales por razones de salud contenido en el \u00a0 Acuerdo PSAA10-6837 de 2010. Respecto de \u00e9ste \u00faltimo su art\u00edculo s\u00e9ptimo \u00a0 dispone: \u00a0 \u00a0<\/p>\n<p>\u201cART\u00cdCULO S\u00c9PTIMO.- los servidores judiciales \u00a0 en carrera, tienen derecho a ser traslados por razones de salud, debidamente \u00a0 comprobadas, a otro despacho judicial, cuando las mismas le hagan imposible \u00a0 continuar en el cargo o por \u00e9stas se encuentre afectado o afectada \u00a0su c\u00f3nyuge, compa\u00f1ero o compa\u00f1era permanente, descendiente o ascendiente en \u00a0 primer grado de consanguinidad o \u00fanico civil\u201d \u00a0 (negrilla fuera del texto). \u00a0 \u00a0<\/p>\n<p>37.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En este orden de ideas, es claro que para \u00a0 aquellos servidores judiciales que pretendan un traslado, por razones de salud, \u00a0 estos deber\u00e1n presentar su solicitud dentro de los primeros cinco (5) d\u00edas \u00a0 h\u00e1biles de cada mes, de acuerdo con las publicaciones de vacantes definitivas \u00a0 que efect\u00fae la Unidad de Administraci\u00f3n de la Carrea Judicial o las Salas \u00a0 Administrativas de los Consejos Seccionales, a trav\u00e9s de la p\u00e1gina web de la \u00a0 Rama Judicial[36]. \u00a0 \u00a0<\/p>\n<p>38.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Respecto de los Magistrados de Tribunal y Consejo \u00a0 Seccional, la solicitud de traslado por razones de salud tendr\u00e1 que ser dirigida \u00a0 y presentada a la Unidad de Administraci\u00f3n de la Carrera Judicial para el respectivo tr\u00e1mite y concepto de la Sala \u00a0 Administrativa del Consejo Superior de la Judicatura. Dicho concepto debe contar \u00a0 con el cumplimiento de los siguientes aspectos, entre otros[37]: (a) \u00a0 el diagn\u00f3stico m\u00e9dico sobre las condiciones de salud que se invocan, cuya fecha \u00a0 de expedici\u00f3n no puede superar los tres (3) meses salvo que se trate de \u00a0 enfermedades cr\u00f3nicas, progresivas, degenerativas o cong\u00e9nitas, en cuyo caso la \u00a0 vigencia del dictamen m\u00e9dico puede ser superior a los tres (3) meses sin \u00a0 sobrepasar los seis (6) meses, debe ser emitido por la entidad promotora de \u00a0 salud (EPS \u2013 IPS) o por la administradora de riesgos profesionales (ARP)[38] a la \u00a0 cual se encuentre afiliado el servidor en el que se recomiende \u00a0 expresamente el traslado por la imposibilidad de continuar desempe\u00f1ando el cargo \u00a0 del cual es titular; (b) la acreditaci\u00f3n del \u00a0 parentesco cuando se trate de enfermedades del c\u00f3nyuge, compa\u00f1era o compa\u00f1ero \u00a0 permanente, descendientes, ascendientes en primer grado de consanguinidad o \u00a0 \u00fanico civil; y (c) en caso de no ser atendida la prescripci\u00f3n m\u00e9dica, la \u00a0 Unidad de Administraci\u00f3n de Carrera Judicial le ofrecer\u00e1 las vacantes existentes \u00a0 al momento, a efectos de obtener el consentimiento expreso del servidor. \u00a0 \u00a0<\/p>\n<p>39.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Una vez realizado el concepto, ser\u00e1 remitido a la \u00a0 entidad nominadora junto con la lista de aspirantes para el cargo vacante, si a \u00a0 ello hubiere lugar, a efectos de que decida sobre el traslado por razones de \u00a0 salud[39]. \u00a0 En todos los casos las autoridades nominadoras deber\u00e1n informar a la Sala \u00a0 Administrativa del Consejo Superior \u2013 Unidad de Administraci\u00f3n de Carrera \u00a0 Judicial, de manera inmediata, seg\u00fan la normatividad vigente, sobre la decisi\u00f3n \u00a0 del traslado o listas de elegibles, para que se realicen las anotaciones \u00a0 respectivas y se ejerza el adecuado control de movimiento de personal[40]. \u00a0 \u00a0<\/p>\n<p>40.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Adicionalmente, es importante destacar que el \u00a0 art\u00edculo 24 del Acuerdo PCSJA17-10754 incorpora una tabla de afinidades para \u00a0 decidir sobre las peticiones de traslado, a fin de determinar si existe \u00a0 similitud entre el cargo de origen y el cargo de destino. \u00a0 \u00a0<\/p>\n<p>\u201cART\u00cdCULO VIG\u00c9SIMO CUARTO.- Tabla de afinidades. \u00a0 Para decidir sobre las peticiones de traslado, en cumplimiento de lo dispuesto \u00a0 en el art\u00edculo 134 de la Ley Estatutaria de la Administraci\u00f3n de Justicia, se \u00a0 deber\u00e1 observar la siguiente tabla de afinidades. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Afinidades \u00a0\u00a0<\/p>\n<p>Cargo de Origen en Propiedad \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Cargo Destino del Traslado \u00a0\u00a0<\/p>\n<p>Juez Promiscuo Municipal. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Juez civil municipal\/ peque\u00f1as causas y competencia m\u00faltiple\/ \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0peque\u00f1as causas laborales\/ penal municipal (con funci\u00f3n de Control de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0garant\u00edas, funci\u00f3n de conocimiento o mixto) \/ penal municipales de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0adolescentes de control de garant\u00edas. \u00a0\u00a0<\/p>\n<p>Juez Promiscuo Circuito. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Juez civil circuito\/ penal circuito\/ laboral circuito\/ civil \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0circuito restituci\u00f3n de tierras. \u00a0\u00a0<\/p>\n<p>Juez Civil Circuito con Conocimiento en Laboral. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Juez civil del circuito\/ laboral del circuito. \u00a0\u00a0<\/p>\n<p>Juez Penal del Circuito y Juez de Ejecuci\u00f3n de Penas y Medidas de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Seguridad. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Juez penal del circuito \/ ejecuci\u00f3n de penas y medidas de seguridad. \u00a0\u00a0<\/p>\n<p>Juez Promiscuo de Familia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Juez de familia \/ penal del circuito de adolescentes. \u00a0\u00a0<\/p>\n<p>Magistrado(a) Sala Civil \u2013 Familia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Magistrado(a) Sala Civil \/ Magistrado(a) Sala Familia \u00a0\u00a0<\/p>\n<p>Magistrado(a) Sala \u00danica \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Magistrado(a) Sala \u00danica \u00a0 \u00a0 \u00a0<\/p>\n<p>41.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Sobre el tr\u00e1mite de traslados de funcionarios \u00a0 judiciales por razones de salud, la Corte Constitucional mediante sentencia \u00a0 T-159 de 2017 precis\u00f3 que \u201clas peticiones de traslado deben ser estudiadas por la Sala \u00a0 Administrativa del Consejo Superior de la Judicatura \u2013Unidad de Administraci\u00f3n \u00a0 de Carrera Judicial\u2013, entidad que debe valorar, cuando las solicitudes sean por \u00a0 razones de salud, documentos tales como los dict\u00e1menes m\u00e9dicos que acreditan el \u00a0 problema de salud del funcionario o de sus familiares y la recomendaci\u00f3n de \u00a0 traslado, la existencia del certificado de vacancia definitiva del cargo al que \u00a0 se pretende el traslado y la manifestaci\u00f3n expresa del deseo del funcionario de \u00a0 ser trasladado a la plaza que se encuentra vacante\u201d. Igualmente, la \u00a0 Corporaci\u00f3n precis\u00f3 que \u201c[e]l concepto favorable emitido no es vinculante \u00a0 pues la decisi\u00f3n final sobre qui\u00e9n ocupar\u00e1 el cargo vacante compete al ente \u00a0 nominador. Sin embargo, sin el aludido concepto, la hoja de vida del funcionario \u00a0 que solicita el traslado no podr\u00e1 ser valorada por el ente nominador, pues s\u00ed es \u00a0 un requisito para que el funcionario sea tenido en cuenta a la hora de elegir \u00a0 quien ocupar\u00e1 la vacante a proveer\u201d. \u00a0 \u00a0<\/p>\n<p>42.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Por su \u00a0 parte, el Consejo de Estado \u2013 Secci\u00f3n Primera en sentencia proferida el 11 de \u00a0 abril de 2018[41] resolvi\u00f3 la acci\u00f3n de tutela \u00a0 presentada por un magistrado del Tribunal Administrativo del Choc\u00f3 al que no le \u00a0 fue emitido un concepto favorable frente a su solicitud de traslado por razones \u00a0 de salud al Tribunal Administrativo del Tolima. En esa ocasi\u00f3n, el alto tribunal \u00a0 de la Jurisdicci\u00f3n de lo Contencioso Administrativo, siguiendo las reglas \u00a0 previstas por la sentencia T-159 de 2017, precis\u00f3 que el m\u00e9rito es el \u00fanico criterio que debe regir el ingreso, la \u00a0 permanencia y el ascenso en la carrera judicial, pues es con base en \u00e9ste, exclusivamente, que las \u00a0 entidades nominadoras deben elegir a los servidores que \u00a0ocupar\u00e1n las vacantes que surjan en sus respectivas jurisdicciones, sin importar \u00a0 el sistema que se emplee para la provisi\u00f3n de los cargos. No obstante, indic\u00f3 el \u00a0 Consejo de Estado que dicha regla encuentra una excepci\u00f3n en materia de \u00a0 traslados por razones de salud al considerarse que, en estos casos, es necesario \u00a0 ponderar el derecho a la salud y la vida del funcionario o de sus familiares \u00a0 frente al derecho a acceder a cargos p\u00fablicos en igualdad de condiciones. \u00a0 \u00a0<\/p>\n<p>43.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En el mismo \u00a0 sentido, el Consejo de Estado ha se\u00f1alado que, en materia de traslados por \u00a0 razones de salud de funcionarios de la rama judicial[42], son \u00a0 aplicables las reglas del derecho de petici\u00f3n en caso de elevarse solicitudes \u00a0 tendientes a conocer la decisi\u00f3n de traslado. De manera que, dicha respuesta \u00a0 debe emitirse dentro de los 15 d\u00edas siguientes a la recepci\u00f3n de la petici\u00f3n y \u00a0 resolver de fondo, de manera clara y de forma congruente a lo pedido, sin que \u00a0 ello implique una respuesta afirmativa. \u00a0 \u00a0<\/p>\n<p>44.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0De otro lado, la Corte Suprema de Justicia, a trav\u00e9s de sentencia de tutela \u00a0 del 12 de diciembre de 2018[43], \u00a0 resolvi\u00f3 el caso de una solicitud de traslado por razones de salud, c\u00e1ncer de \u00a0 col\u00f3n, de una magistrada del Tribunal Superior del Distrito. En esa oportunidad, \u00a0 el amparo fue concedido toda vez que el ente nominador no tuvo en cuenta la \u00a0 gravedad de la enfermedad padecida por la accionante y la imposibilidad de \u00a0 tratarla en la ciudad de Sincelejo. No obstante, en dicha providencia, con base \u00a0 en las sentencias proferidas por la Corte Constitucional, a saber, las \u00a0 sentencias T-488 de 2004 y T-947 de 2012, la Sala de Casaci\u00f3n Civil aclar\u00f3 que \u00a0 si bien es cierto que constitucional y legalmente la autoridad nominadora puede \u00a0 denegar la petici\u00f3n de traslado a pesar del concepto favorable que aval\u00f3 su \u00a0 procedencia, esa decisi\u00f3n debe basarse en criterios objetivos, concretos y \u00a0 razonados, para evitar la arbitrariedad y el quebranto de los derechos de los \u00a0 funcionarios y empleados. En este orden de ideas, la Corte Suprema de Justicia[44] \u00a0ha se\u00f1alado que se vulnera el debido proceso administrativo cuando existe falsa \u00a0 motivaci\u00f3n en la respuesta frente a la solicitud de traslado por razones de \u00a0 salud, pues dichas solicitudes no pueden negarse con base en aspectos personales \u00a0 dado que ello desconoce el principio del m\u00e9rito como criterio de ingreso en la \u00a0 carrera judicial. \u00a0 \u00a0<\/p>\n<p>45.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Acorde con lo expuesto \u00a0 en precedencia, las solicitudes de traslado por razones de salud de magistrados \u00a0 de Tribunal (Superior del Distrito Judicial o Administrativos) deben tramitarse \u00a0 de conformidad con lo previsto en el PCSJA17-10754 de \u00a0 2017 expedido por la Presidencia del Consejo \u00a0 Superior de la Judicatura, que reproduce las disposiciones previstas en el \u00a0 PSAA10-6837 de 2010, seg\u00fan el mismo sea modificado, el cual supone el \u00a0 cumplimiento de t\u00e9rminos para la presentaci\u00f3n de tales solicitudes y la \u00a0 valoraci\u00f3n de unos requisitos, a efectos de que la Sala Administrativa del \u00a0 Consejo Superior de la Judicatura pueda emitir un concepto sobre dicha \u00a0 solicitud, este \u00faltimo requisito sin el cual el funcionario judicial no puede \u00a0 ser evaluado para la vacante. Cabe destacar que, aun cuando tal concepto no \u00a0 obliga al ente nominador, la decisi\u00f3n de negar o aceptar el traslado solicitado \u00a0debe basarse en \u00a0 criterios objetivos, concretos y razonados, a fin de no vulnerar el principio \u00a0 del m\u00e9rito y el acceso a cargos p\u00fablicos. Una vez decidida, deber\u00e1 informarse al \u00a0 interesado, o podr\u00eda ser requerida la informaci\u00f3n sobre la decisi\u00f3n por el \u00a0 solicitante mediante escrito de petici\u00f3n a la entidad nominadora, el cual debe \u00a0 contestarse dentro de los 15 d\u00edas h\u00e1biles siguientes de forma clara, de fondo y \u00a0 congruente. \u00a0 \u00a0<\/p>\n<p>E.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0SOLUCI\u00d3N AL CASO \u00a0 CONCRETO \u00a0 \u00a0<\/p>\n<p>46.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En el caso estudiado por \u00a0 la Sala en esta oportunidad, el problema jur\u00eddico a resolver consiste en \u00a0 determinar si la Sala Plena de la Corte Suprema de \u00a0 Justicia, en calidad de ente nominador, vulner\u00f3 los derechos fundamentales al \u00a0 debido proceso administrativo, a la igualdad, a la salud y al trabajo en \u00a0 condiciones dignas del se\u00f1or \u00c1lvaro Vincos Urue\u00f1a al negarle el traslado por \u00a0 razones de salud que solicit\u00f3 para el cargo vacante de Magistrado de la Sala \u00a0 Penal del Tribunal Superior del Distrito Judicial de Bogot\u00e1, pese a que (a) \u00a0 contaba con una recomendaci\u00f3n m\u00e9dica; y (b) el concepto favorable de la Unidad \u00a0 de Administraci\u00f3n de Carrera Judicial. \u00a0 \u00a0<\/p>\n<p>47.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Conforme con los \u00a0 elementos probatorios visibles en el expediente, la Sala advierte que (i) el 6 \u00a0 de mayo de 2015, \u00c1lvaro Vincos Urue\u00f1a se posesion\u00f3 en propiedad en el cargo de \u00a0 Magistrado de la Sala \u00danica del Tribunal Superior del Distrito Judicial de Yopal[45]; (ii) \u00a0 el 5 de junio de 2017, ante la Unidad de Administraci\u00f3n de Carrera Judicial \u00a0 elev\u00f3 solicitud de traslado por razones de salud, para ocupar el cargo de \u00a0 Magistrado de la Sala Penal del Tribunal Superior del Distrito Judicial de \u00a0 Bogot\u00e1 en reemplazo del Doctor Orlando Mu\u00f1oz Neira[46] y anex\u00f3 copia de su historia \u00a0 cl\u00ednica, espec\u00edficamente, la consulta de control del d\u00eda 8 de febrero de 2017 en \u00a0 la que se indica que el accionante padece de sinusitis y rinitis cr\u00f3nica, y \u201cal \u00a0 paciente se le ha sugerido traslado de residencia y reubicaci\u00f3n laboral a clima \u00a0 templado o fr\u00edo\u201d[47]; \u00a0 (iii) el 27 de julio de 2017, la Unidad de Administraci\u00f3n de Carrera Judicial \u00a0 emiti\u00f3 concepto favorable de traslado por razones de salud a la solicitud del \u00a0 se\u00f1or Vincos Urue\u00f1a. Al respecto se\u00f1al\u00f3: \u201cteniendo en cuenta que el \u00a0 diagn\u00f3stico relaciona una patolog\u00eda de car\u00e1cter cr\u00f3nico y existe una \u00a0 recomendaci\u00f3n clara y expresa por parte del m\u00e9dico tratante, en la cual se \u00a0 expresa la necesidad de traslado de residencia y reubicaci\u00f3n laboral a un clima \u00a0 templado o fr\u00edo como lo es la ciudad de Bogot\u00e1, se hallan los presupuestos \u00a0 necesarios para la viabilidad del traslado\u201d. \u00a0 \u00a0<\/p>\n<p>48.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El 22 de noviembre de \u00a0 2017, el se\u00f1or Vincos Urue\u00f1a present\u00f3 petici\u00f3n al Presidente de la Corte Suprema \u00a0 de Justicia, a efectos de que le fuera informada la decisi\u00f3n sobre su solicitud \u00a0 de traslado[48]; \u00a0 (v) el 6 de diciembre de 2017, la Presidencia de la Corte Suprema de Justicia \u00a0 respondi\u00f3 a dicha solicitud del accionante, precisando que las razones objetivas \u00a0 por las cuales no fue aceptada su solicitud de traslado obedecieron a que \u201cel \u00a0 asunto fue sometido a consideraciones de la plenaria y en virtud de que la \u00a0 solicitud no obtuvo el n\u00famero de votos favorables requeridos para ser aprobada, \u00a0 no fue trasladado\u201d. \u00a0 \u00a0<\/p>\n<p>49.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0De manera preliminar, se \u00a0 puede concluir que el accionante present\u00f3 su solicitud de traslado por razones \u00a0 de salud conforme con lo previsto en el Acuerdo PSAA10-6837 de 2010, vigente \u00a0 para el momento de los hechos, toda vez que elev\u00f3 su petici\u00f3n ante la Unidad de \u00a0 Administraci\u00f3n de Carrera Judicial el d\u00eda 5 del mes de junio del 2017, a fin de \u00a0 que se efectuara el concepto requerido para que su solicitud fuera evaluada por \u00a0 el ente nominador. As\u00ed mismo, adjunt\u00f3 como anexo en su petici\u00f3n de traslado un \u00a0 certificado m\u00e9dico de su padre con un padecimiento, sin embargo, la solicitud de \u00a0 traslado se fundament\u00f3 exclusivamente en su propia condici\u00f3n de salud, sin \u00a0 profundizar o poner en conocimiento la necesidad de ser trasladado por razones \u00a0 de salud de su padre, como tampoco se\u00f1al\u00f3 las motivaciones que conllevar\u00edan a \u00a0 que fuese necesario el traslado para que el funcionario judicial pudiese estar \u00a0 al lado de su padre. Por lo cual, entiende la Sala que la verdadera motivaci\u00f3n \u00a0 del accionante fue la de solicitar a la Unidad de Administraci\u00f3n de Carrera \u00a0 Judicial el visto bueno para el traslado, por razones de su propia condici\u00f3n. \u00a0 \u00a0<\/p>\n<p>50.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Ahora bien, con ocasi\u00f3n \u00a0 de las pruebas solicitadas por el juez constitucional, se pudo constatar que el \u00a0 accionante fue nombrado en propiedad en el cargo de Magistrado de la Sala Penal \u00a0 del Tribunal Superior del Distrito Judicial de Bogot\u00e1, el d\u00eda 1\u00b0 de febrero de \u00a0 2019. \u00a0 \u00a0<\/p>\n<p>51.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0No obstante, la Sala no comparte lo decidido en \u00a0 las sentencias de instancia impugnadas, por cuanto, dichos fallos se apartan de los postulados de la Constituci\u00f3n. En este sentido, es preciso destacar que acorde con la \u00a0 jurisprudencia constitucional el concepto que emite la Unidad de Administraci\u00f3n \u00a0 de Carrera Judicial no tiene el car\u00e1cter de vinculante para el ente nominador, \u00a0 toda vez que hace parte de su facultad discrecional decidir sobre los traslados \u00a0 por razones de salud. No obstante, la Corte tambi\u00e9n ha reconocido que las \u00a0 razones que nieguen el traslado deben atender a motivos objetivos, concretos y \u00a0 razonados, a fin de preservar el principio del m\u00e9rito y el acceso a los cargos \u00a0 p\u00fablicos. \u00a0 \u00a0<\/p>\n<p>52.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Ahora bien, de \u00a0 conformidad con los medios de prueba aportados en sede de revisi\u00f3n, es posible \u00a0 concluir que las razones por las cuales la Sala Plena de la Corte Suprema de \u00a0 Justicia neg\u00f3 el traslado solicitado por el se\u00f1or Vincos Urue\u00f1a, pese al \u00a0 concepto favorable emitido por la Unidad de Administraci\u00f3n de Carrera Judicial, \u00a0 no se refirieron a motivos subjetivos, sino que, por el contrario, aluden a \u00a0 razones objetivas, concretas y razonadas inspiradas en el respeto por el \u00a0 principio del m\u00e9rito y la carrera judicial, pues el punto central de la \u00a0 discusi\u00f3n gir\u00f3 en la imposibilidad de permitir el traslado entre cargos \u00a0 distintos, dado que el se\u00f1or Vincos Urue\u00f1a ostentaba la calidad de Magistrado de \u00a0 la Sala \u00danica del Tribunal Superior del Distrito Judicial de Yopal y pretend\u00eda \u00a0 su nombramiento como Magistrado de la Sala Penal del Tribunal Superior del \u00a0 Distrito Judicial de Bogot\u00e1, es decir, una sala especializada. Adicionalmente, \u00a0 la Sala Plena de la Corte Suprema de Justicia tambi\u00e9n advirti\u00f3 mediante oficio \u00a0 remitido en sede de revisi\u00f3n que la enfermedad padecida por el demandante no \u00a0 tiene la gravedad suficiente para imposibilitarlo en el ejercicio de sus labores \u00a0 en el Tribunal Superior del Distrito Judicial de Yopal. Llama la atenci\u00f3n la \u00a0 Sala al hecho que las solicitudes de petici\u00f3n que le sean formuladas, diferentes \u00a0 a aquellas que se refieran al ejercicio de las funciones jurisdiccionales[49], \u00a0 deben cumplir con los requisitos m\u00ednimos establecidos en la jurisprudencia de \u00a0 este Tribunal, a saber, (i) la pronta resoluci\u00f3n del mismo, es decir que la respuesta debe \u00a0 entregarse dentro del t\u00e9rmino legalmente establecido para ello; y (ii) la \u00a0 contestaci\u00f3n debe ser clara y efectiva respecto de lo pedido, de tal manera que \u00a0 permita al peticionario conocer la situaci\u00f3n real de lo solicitado, sin que ello \u00a0 signifique que la soluci\u00f3n tenga que ser positiva. \u00a0 \u00a0<\/p>\n<p>53.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En este sentido vale la \u00a0 pena traer a colaci\u00f3n la intervenci\u00f3n, en sede de revisi\u00f3n, de la Unidad de \u00a0 Administraci\u00f3n de Carrera Judicial, pues en ella se resalt\u00f3 que las pruebas para \u00a0 el concurso de m\u00e9ritos que se realizan para cubrir las vacantes de magistrado de \u00a0 Sala \u00danica de Tribunal y las de magistrado de Sala Especializada de Tribunal no \u00a0 son equiparables, dado que corresponden a diferentes especialidades, as\u00ed como \u00a0 los asuntos y temas de estudio que en desarrollo de sus funciones deben atender[50]. \u00a0 \u00a0<\/p>\n<p>54.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En este orden de ideas, \u00a0 despu\u00e9s de que la Sala analiz\u00f3 dicha informaci\u00f3n pudo observar que los ejes \u00a0 tem\u00e1ticos que se aplican en las pruebas son diferentes, comoquiera que a los \u00a0 magistrados de Sala \u00danica de Tribunal no se les eval\u00faan sus conocimientos en \u00a0 materia penal sobre \u201clas audiencias preliminares, preparatoria y de \u00a0 juzgamiento, juzgamiento de los delitos en general que sean de su competencia, \u00a0 ejecuci\u00f3n sentencias penales. Derecho sustancial\u201d, y a los magistrados de \u00a0 Sala Especializada Penal de Tribunal no se le eval\u00faan conocimientos sobre temas \u00a0 de derecho civil y de derecho laboral que s\u00ed deben preparar y presentar los \u00a0 aspirantes al cargo de magistrado de Sala \u00danica de Tribunal[51]. Por \u00a0 consiguiente, para la Sala no cabe duda de que el concurso para suplir la \u00a0 vacante de magistrado de Sala Especializada de Tribunal eval\u00faa con mayor \u00a0 profundidad una \u00fanica \u00e1rea del derecho, a la que se refiere la especialidad del \u00a0 cargo. De la misma forma, se evidencian que los asuntos y temas de estudio en \u00a0 desarrollo de sus funciones son diferentes, as\u00ed como la preparaci\u00f3n que reciben \u00a0 los funcionarios judiciales para el desempe\u00f1o de su funci\u00f3n -seg\u00fan lo se\u00f1alado \u00a0 la Escuela Judicial Rodrigo Lara Bonilla, divide los cursos de magistrados de \u00a0 Sala Especializada de Tribunal de magistrados de Sala \u00danica de Tribunal. De lo \u00a0 cual es dado afirmar que la decisi\u00f3n adoptada por la Sala Plena de la Corte \u00a0 Suprema de Justicia exalta el m\u00e9rito en la carrera judicial, e interpreta de \u00a0 forma correcta el r\u00e9gimen de ingreso, permanencia y ascenso en la misma. \u00a0 \u00a0<\/p>\n<p>55.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Con fundamento en lo \u00a0 anterior, esta Sala de Revisi\u00f3n estima que la diferencia entre los cargos de \u00a0 magistrado de Sala \u00danica de Tribunal y magistrado de Sala Especializada de \u00a0 Tribunal es una raz\u00f3n objetiva, concreta y razonable suficiente para negar la \u00a0 solicitud de traslado por razones de salud presentada por el se\u00f1or Vincos \u00a0 Urue\u00f1a, comoquiera que tal solicitud no se ajusta al supuesto previsto en el \u00a0 art\u00edculo 134 de la Ley Estatutaria de Administraci\u00f3n de Justicia al no ser \u00a0 cargos afines. En ese sentido, para la Sala no existi\u00f3 una vulneraci\u00f3n de los \u00a0 derechos fundamentales al debido proceso, a la salud, al trabajo y a la igualdad \u00a0 del se\u00f1or \u00c1lvaro Vincos Urue\u00f1a. \u00a0 \u00a0<\/p>\n<p>56.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0De otro lado, en cuanto \u00a0 a la precisi\u00f3n que hizo la Sala Plena de la Corte Suprema de Justicia sobre la \u00a0 gravedad del padecimiento m\u00e9dico del actor, esta Sala de Revisi\u00f3n, contrario a \u00a0 lo manifestado por el juez constitucional de segunda instancia, estima que tal \u00a0 argumento no implica una motivaci\u00f3n subjetiva frente a la negativa del traslado \u00a0 solicitado por el se\u00f1or Vincos Urue\u00f1a, ya que el art\u00edculo 7\u00ba del Acuerdo \u00a0 PSAA10-6837 de 2010 autoriza tal valoraci\u00f3n al precisar que las razones de salud \u00a0 deben (i) estar debidamente comprobadas; e (ii) imposibilitar la continuaci\u00f3n en \u00a0 el cargo[52]. \u00a0 Al respecto, llama la atenci\u00f3n de la Sala que el concepto m\u00e9dico valorado por la \u00a0 mencionada Unidad de Administraci\u00f3n de Carrera Judicial no se encuadra dentro \u00a0 del supuesto previsto en el art\u00edculo 9\u00ba del Acuerdo PSAA10-6837 de 2010, el cual \u00a0 dispone que el diagn\u00f3stico m\u00e9dico debe recomendar expresamente el traslado por \u00a0 la imposibilidad de continuar desempe\u00f1ando el cargo. Sobre el particular: \u00a0 \u00a0<\/p>\n<p>\u201cART\u00cdCULO \u00a0 NOVENO. Concepto. Para efectos de emitir concepto sobre las peticiones de \u00a0 traslado por razones de salud, los Consejos Superior y Seccionales tendr\u00e1n en \u00a0 cuenta entre otros aspectos los siguientes: a) El diagn\u00f3stico m\u00e9dico \u00a0sobre las condiciones de salud que se invocan, expedido en los t\u00e9rminos \u00a0 se\u00f1alados en el art\u00edculo octavo de este Acuerdo, en el cual se recomiende \u00a0 expresamente el traslado por la imposibilidad de continuar desempe\u00f1ando el cargo \u00a0 del cual es titular\u201d (negrilla fuera del texto). \u00a0 \u00a0<\/p>\n<p>57.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Lo anterior tambi\u00e9n \u00a0 encuentra justificaci\u00f3n en la consulta m\u00e9dica de control, del d\u00eda 16 de \u00a0 diciembre de 2017, en la que el m\u00e9dico tratante del demandante se\u00f1ala \u201cpaciente \u00a0 con rinosinusitis cr\u00f3nica, presenta s\u00edntomas rinosinusuales recurrentes que \u00a0 mejoran con tratamiento m\u00e9dico y se empeoran con cambios clim\u00e1ticos\u201d[53]. En \u00a0 consecuencia, para la Sala tampoco existe una vulneraci\u00f3n al derecho fundamental \u00a0 a la salud del actor, toda vez que el ente nominador, en estricta observancia \u00a0 del r\u00e9gimen de traslados por razones de salud y de la jurisprudencia \u00a0 constitucional, valor\u00f3 su padecimiento m\u00e9dico en relaci\u00f3n con el desempe\u00f1o del \u00a0 cargo y no encontr\u00f3 una raz\u00f3n suficiente que justificara el traslado. En ese \u00a0 sentido, para esta Sala era indispensable que la recomendaci\u00f3n m\u00e9dica indicara \u00a0 de manera inequ\u00edvoca que la patolog\u00eda del se\u00f1or Vincos Urue\u00f1a le imposibilitaba \u00a0 continuar sus labores en la ciudad de Yopal, sin embargo, ello no se encuentra \u00a0 expuesto en la mencionada recomendaci\u00f3n y en su lugar, se observa que los \u00a0 s\u00edntomas del se\u00f1or Vincos Urue\u00f1a mejoran con el tratamiento m\u00e9dico prescrito. \u00a0 \u00a0<\/p>\n<p>En este orden de ideas, aun cuando el m\u00e9dico tratante \u00a0 del accionante sugiere el traslado de residencia a clima templado o fr\u00edo, dicha \u00a0 recomendaci\u00f3n no se\u00f1ala que exista una imposibilidad, derivada del padecimiento \u00a0 m\u00e9dico del se\u00f1or Vincos Urue\u00f1a, para desempe\u00f1ar el cargo en el municipio de \u00a0 Yopal. De manera que la recomendaci\u00f3n no se ajusta al supuesto previsto en el \u00a0 art\u00edculo 9\u00ba del Acuerdo PSAA10-6837 de 2010. \u00a0 \u00a0<\/p>\n<p>58.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Finalmente, es \u00a0 importante destacar que la restituci\u00f3n del accionante en el cargo de magistrado \u00a0 de Sala \u00danica del Tribunal Superior del Distrito Judicial de Yopal, que se \u00a0 ordenar\u00e1 en la presente providencia, no afecta ning\u00fan derecho de la se\u00f1ora Mar\u00eda \u00a0 Stella Jara Guti\u00e9rrez, comoquiera que fue vinculada en provisionalidad en el \u00a0 citado cargo, es decir, hasta tanto se hiciera el nombramiento de manera \u00a0 definitiva. Sobre el particular, esta Corte ha manifestado que \u201clos servidores nombrados en \u00a0 provisionalidad en cargos de carrera, tal y como lo ha reconocido esta \u00a0 corporaci\u00f3n en reiterados pronunciamientos, gozan de una estabilidad laboral \u00a0 relativa o intermedia, que se traduce en que su retiro del servicio p\u00fablico solo \u00a0 tendr\u00e1 lugar por causales objetivas previstas en la Constituci\u00f3n y en la ley, o \u00a0 para proveer el cargo que ocupan con una persona que haya superado \u00a0 satisfactoriamente el respectivo concurso de m\u00e9ritos\u201d[54]. \u00a0 \u00a0<\/p>\n<p>En consecuencia, dado que la permanencia en el cargo de \u00a0 magistrado de Sala \u00danica del Tribunal Superior del Distrito Judicial de Yopal \u00a0 que ostentaba la se\u00f1ora Mar\u00eda Stella Jara Guti\u00e9rrez estaba sujeta a la no \u00a0 provisi\u00f3n definitiva del mismo, una vez restituido el se\u00f1or Vincos Urue\u00f1a a \u00a0 dicho cargo cede a la provisi\u00f3n del m\u00e9rito. \u00a0 \u00a0<\/p>\n<p>59.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Acorde con lo expuesto \u00a0 en precedencia, la Sala Cuarta de Revisi\u00f3n revocar\u00e1 las decisiones proferidas el 10 de mayo y el 15 de noviembre de 2018 por la Corte \u00a0 Suprema de Justicia en sus Salas de Casaci\u00f3n Penal y Civil, y en su lugar, \u00a0 primero declarar\u00e1 la carencia actual de objeto por hecho superado. Por consiguiente, la Sala ordenar\u00e1 por conducto del \u00a0 ente nominador, que dentro de los cinco (5) d\u00edas siguientes a la notificaci\u00f3n de \u00a0 la presente sentencia, se restituya al se\u00f1or \u00c1lvaro Vincos Urue\u00f1a al cargo de \u00a0 magistrado de Sala \u00danica del Tribunal Superior del Distrito Judicial de Yopal y \u00a0 que cese el nombramiento en provisionalidad de Mar\u00eda Stella Jara Guti\u00e9rrez, \u00a0 quien fue nombrada en sesi\u00f3n extraordinaria de la Sala Plena de la Corte Suprema \u00a0 de Justicia el 12 de marzo de 2019, a fin de no vulnerar los derechos de carrera \u00a0 del accionante. \u00a0 \u00a0<\/p>\n<p>F.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0S\u00cdNTESIS DE LA DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>60.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Le correspondi\u00f3 a la \u00a0 Sala Cuarta de Revisi\u00f3n de la Corte Constitucional \u00a0 determinar si la Sala Plena de la Corte Suprema de Justicia, en calidad de ente \u00a0 nominador, vulner\u00f3 los derechos fundamentales al debido proceso administrativo, \u00a0 a la igualdad, a la salud y al trabajo en condiciones dignas del se\u00f1or \u00c1lvaro \u00a0 Vincos Urue\u00f1a al negarle el traslado por razones de salud que solicit\u00f3 para el \u00a0 cargo vacante de Magistrado de la Sala Penal del Tribunal Superior del Distrito \u00a0 Judicial de Bogot\u00e1, pese a que (a) contaba con una recomendaci\u00f3n m\u00e9dica; y (b) \u00a0 con el concepto favorable de la Unidad de Administraci\u00f3n de Carrera Judicial. \u00a0 \u00a0<\/p>\n<p>61.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Como resultado de las sub-reglas \u00a0 jurisprudenciales analizadas en la parte motiva de esta providencia, observa la \u00a0 Sala lo siguiente: \u00a0 \u00a0<\/p>\n<p>(i)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Procede de manera \u00a0 excepcional la acci\u00f3n de tutela contra actos administrativos que decidan el \u00a0 traslado de funcionarios judiciales por razones de salud, aun cuando los mismos \u00a0 podr\u00edan recurrirse a trav\u00e9s del medio de control de nulidad y restablecimiento \u00a0 del derecho y\u00a0 ser objeto de las medidas cautelares previstas en los \u00a0 art\u00edculos 229 y 230 del C\u00f3digo de Procedimiento Administrativo y de lo \u00a0 Contencioso Administrativo, en caso de que el juez de tutela advierta que dicho \u00a0 acto presuntamente est\u00e1 afectando los derechos que se derivan de la carrera \u00a0 judicial, y potencialmente deriven en una afectaci\u00f3n al derecho a la salud del \u00a0 accionante. \u00a0 \u00a0<\/p>\n<p>(ii)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Las solicitudes de \u00a0 traslado por razones de salud de magistrados de Tribunal (Superior del Distrito \u00a0 Judicial o Administrativos) deben tramitarse de conformidad con lo previsto en \u00a0 el PCSJA17-10754 de 2017 \u00a0expedido por la Presidencia del Consejo Superior de la Judicatura, que reproduce \u00a0 las disposiciones previstas en el PSAA10-6837 de 2010, el cual supone el \u00a0 cumplimiento de t\u00e9rminos para la presentaci\u00f3n de tales solicitudes y la \u00a0 valoraci\u00f3n de unos requisitos, a efectos de que la Sala Administrativa del \u00a0 Consejo Superior de la Judicatura pueda emitir un concepto sobre dicha \u00a0 solicitud, requisito sin el cual el funcionario judicial no puede ser evaluado \u00a0 para la vacante. Cabe destacar que, aun cuando tal concepto no obliga al ente \u00a0 nominador, la decisi\u00f3n de negar o aceptar el traslado solicitado debe basarse en criterios \u00a0 objetivos, concretos y razonados, a fin de no vulnerar el principio del m\u00e9rito y \u00a0 el acceso a cargos p\u00fablicos. En este sentido, observa la Sala que en el presente \u00a0 caso las razones de la Sala Plena de la Corte Suprema de Justicia, para negar el \u00a0 traslado por razones de salud, cumplen con los criterios se\u00f1alados en la \u00a0 jurisprudencia, al considerar que no era posible autorizar dicho traslado debido \u00a0 a que (i) los cargos de magistrado de Sala \u00danica de Tribunal y Magistrado de \u00a0 Sala Especializada de Tribunal no son afines, de conformidad con lo dispuesto en \u00a0 el art\u00edculo 134 de la Ley Estatutaria de Administraci\u00f3n de Justicia; y (ii) el \u00a0 padecimiento m\u00e9dico del solicitante no lo imposibilita para continuar en el \u00a0 cargo. \u00a0 \u00a0<\/p>\n<p>62.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0En consecuencia, aun cuando la Sala de Revisi\u00f3n revocar\u00e1 las decisiones de \u00a0 instancia y ordenar\u00e1 que por \u00a0 conducto del ente nominador que, dentro de los cinco (5) d\u00edas siguientes a la \u00a0 notificaci\u00f3n de la presente sentencia, se restituya al se\u00f1or \u00c1lvaro Vincos \u00a0 Urue\u00f1a al cargo de Magistrado de Sala \u00danica del Tribunal Superior del Distrito \u00a0 Judicial de Yopal y que cese el nombramiento en provisionalidad de Mar\u00eda Stella \u00a0 Jara Guti\u00e9rrez, quien fue nombrada en sesi\u00f3n extraordinaria de la Sala Plena de \u00a0 la Corte Suprema de Justicia el 12 de marzo de 2019, a fin de no vulnerar los \u00a0 derechos de carrera del accionante. \u00a0 \u00a0<\/p>\n<p>III.\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo \u00a0 expuesto, la Sala Cuarta de Revisi\u00f3n de la Corte Constitucional de la Rep\u00fablica \u00a0 de Colombia, administrando justicia en nombre del pueblo y por mandato de la \u00a0 Constituci\u00f3n,\u00a0 \u00a0 \u00a0<\/p>\n<p>RESUELVE \u00a0 \u00a0<\/p>\n<p>PRIMERO.- REVOCAR las sentencias proferidas el 10 de mayo y el 15 de noviembre de 2018 por la Corte Suprema de \u00a0 Justicia en sus Salas de Casaci\u00f3n Penal y Civil, respectivamente. \u00a0 \u00a0<\/p>\n<p>SEGUNDO.- ORDENAR a la Sala \u00a0 Plena de la Corte Suprema de Justicia que, dentro de los cinco (5) d\u00edas \u00a0 siguientes a la notificaci\u00f3n de la presente sentencia, restituya al se\u00f1or \u00c1lvaro \u00a0 Vincos Urue\u00f1a al cargo de magistrado de la Sala \u00danica del Tribunal Superior del \u00a0 Distrito Judicial de Yopal y, en consecuencia, CESAR el nombramiento en provisionalidad de Mar\u00eda \u00a0 Stella Jara Guti\u00e9rrez, quien fue nombrada en sesi\u00f3n extraordinaria de la Sala \u00a0 Plena de la Corte Suprema de Justicia el 12 de marzo de 2019, a fin de no \u00a0 vulnerar los derechos de carrera del accionante. \u00a0 \u00a0<\/p>\n<p>TERCERO.- Por Secretar\u00eda \u00a0 General, L\u00cdBRENSE las comunicaciones de que trata el art\u00edculo 36 del \u00a0 Decreto 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese, c\u00famplase. \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>ALEJANDRO LINARES CANTILLO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>ANTONIO \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0JOS\u00c9 LIZARAZO OCAMPO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>GLORIA \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0STELLA ORTIZ DELGADO \u00a0 \u00a0<\/p>\n<p>Magistrada \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0 \u00a0<\/p>\n<p>Secretaria \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0General \u00a0 \u00a0 \u00a0<\/p>\n<p>[1] Folios 1 \u2013 8 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[2] Folios 110 \u2013 111 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[3] Folios 9 &#8211; 12 cuaderno No. 1. Dicho documento se\u00f1ala que \u201cal \u00a0 cumplirse los presupuestos fijados para la procedencia del traslado por razones \u00a0 de salud para el cargo de Magistrado de la Sala Penal del Tribunal Superior del \u00a0 Distrito Judicial de Bogot\u00e1 D.C. que solicita el doctor \u00c1lvaro Vincos Urue\u00f1a, \u00a0 esta unidad emite concepto favorable de traslado\u201d. \u00a0 \u00a0<\/p>\n<p>[4] Folio 30 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[5] Folios 31 \u2013 32 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[6] Folios 120 \u2013 122 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[7] Folio 112 cuaderno No. 1. Acorde con el registro m\u00e9dico \u00a0 expedido por un otorrino vinculado a la EPS Sanitas, de fecha 8 de febrero de \u00a0 2017. Igualmente, mediante consulta m\u00e9dica del 16 de diciembre de 2017 se deja \u00a0 constancia que es un \u201cpaciente con rinosinusitis cr\u00f3nica, presenta s\u00edntomas \u00a0 rinosinusuales recurrentes que mejoran con tratamiento m\u00e9dico y se empeoran con \u00a0 cambios clim\u00e1ticos. Se le ha sugerido traslado de residencia a clima templado o \u00a0 fr\u00edo pero a\u00fan permanece en clima c\u00e1lido con uso cotidiano de aire acondicionado\u201d \u00a0 (folio 127 cuaderno No. 1.). \u00a0 \u00a0<\/p>\n<p>[8] El 23 de abril de 2018, los magistrados de la Sala de \u00a0 Casaci\u00f3n Penal de la Corte Suprema de Justicia manifestaron impedimento para \u00a0 conocer de la tutela de la referencia, por cuanto integran la Sala demandada y \u00a0 participaron de la cesi\u00f3n en la que se resolvi\u00f3 de manera desfavorable la \u00a0 petici\u00f3n presentada por el actor. En consecuencia, remitieron el asunto a la \u00a0 Secretar\u00eda de la Sala Penal con el prop\u00f3sito de que se surtiera el sorteo de \u00a0 conjueces (folio 135 cuaderno No. 1.). El 2 de mayo de 2018, los conjueces \u00a0 Carlos Roberto Solorzano Garavito, Ricardo Posada Maya y Ra\u00fal Cadena Lozano \u00a0 aceptaron el impedimento manifestado por los magistrados de la Sala de Casaci\u00f3n \u00a0 Penal de la Corte Suprema de Justicia y los separaron del conocimiento del \u00a0 asunto (folio 145 cuaderno No. 1.). \u00a0 \u00a0<\/p>\n<p>[9] Folios 211 \u2013 230, 234, 236 \u2013 240 y 248 &#8211; 249 Acorde con las \u00a0 pruebas solicitadas en la primera instancia. \u00a0 \u00a0<\/p>\n<p>[10] Folios 242 \u2013 243 cuaderno No. 1. Acorde con las pruebas \u00a0 solicitadas en primera instancia. \u00a0 \u00a0<\/p>\n<p>[11] Folios 181 y 209 \u2013 210 cuaderno No. 1. Acorde con las pruebas \u00a0 solicitadas en primera instancia. \u00a0 \u00a0<\/p>\n<p>[12] Folios 253 \u2013 275 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[13] Folios 303 \u2013 304 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[14] Debido a que los magistrados de la Sala de Casaci\u00f3n Civil de \u00a0 la Corte Suprema de Justicia manifestaron impedimento para conocer de la tutela \u00a0 de la referencia (folios 4 -18 cuaderno No. 2) el 10 de julio de 2018 se hizo \u00a0 sorteo de conjueces (folio 19 cuaderno No. 2). \u00a0 \u00a0<\/p>\n<p>[15] Folios 205 \u2013 223 cuaderno No. 2. \u00a0 \u00a0<\/p>\n<p>[16] Auto de pruebas del 10 de abril de 2019. Folios 42 &#8211; 43 cuaderno \u00a0 principal. \u00a0 \u00a0<\/p>\n<p>[17] Auto adicional de pruebas del 29 de abril de 2019. \u00a0 \u00a0<\/p>\n<p>[18] Mediante oficios Nos. OPTB-803 (folios 44 &#8211; 45 cuaderno principal), \u00a0 OPTB- 804 (folio 46\u00a0 cuaderno principal),\u00a0 OPTB- 805 (folio 47 \u00a0 cuaderno principal) y OPTB 807 (folio 67 cuaderno principal) se envi\u00f3 la \u00a0 solicitud de pruebas al accionante, a la Sala Administrativa del Consejo \u00a0 Superior de la Judicatura, a la Unidad de Administraci\u00f3n de Carrera Judicial y a \u00a0 la Secretar\u00eda General de la Corte Suprema de Justicia, respectivamente. \u00a0 \u00a0<\/p>\n<p>[19] Folios 49 \u2013 50 cuaderno principal. Se adjunt\u00f3 Acta de Posesi\u00f3n No. \u00a0 002 del 1 de febrero de 2019. \u00a0 \u00a0<\/p>\n<p>[20] Folios 52 \u2013 62 cuaderno principal. \u00a0 \u00a0<\/p>\n<p>[21] Folios 71 \u2013 72 y 74 \u2013 75 cuaderno principal. \u00a0 \u00a0<\/p>\n<p>[22] Folios 76 \u2013 78 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[23] Folios 81 \u2013 82 y 84 \u2013 85 cuaderno principal. \u00a0 \u00a0<\/p>\n<p>[24] Ver, entre otras, sentencias T-119 de 2015, T-250 de 2015, T-446 de \u00a0 2015, T-548 de 2015, y T-317 de 2015. \u00a0 \u00a0<\/p>\n<p>[25] Decreto 2591 de 1991, art\u00edculo 8. La tutela \u00a0 como mecanismo transitorio. \u201cAun cuando el afectado disponga de otro medio de \u00a0 defensa judicial, la acci\u00f3n de tutela proceder\u00e1 cuando se utilice como mecanismo \u00a0 transitorio para evitar un perjuicio irremediable. En el caso del inciso \u00a0 anterior, el juez se\u00f1alar\u00e1 expresamente en la sentencia que su orden permanecer\u00e1 \u00a0 vigente s\u00f3lo durante el t\u00e9rmino que la autoridad judicial competente utilice \u00a0 para decidir de fondo sobre la acci\u00f3n instaurada por el afectado. En todo caso \u00a0 el afectado deber\u00e1 ejercer dicha acci\u00f3n en un t\u00e9rmino m\u00e1ximo de cuatro (4) meses \u00a0 a partir del fallo de tutela.\u00a0(\u2026)\u201d. \u00a0 \u00a0<\/p>\n<p>[26] Ver sentencia C-378 de 2010. En esa ocasi\u00f3n la Corte Constitucional \u00a0 estudi\u00f3 la demanda de inconstitucionalidad contra el\u00a0 numeral 3\u00ba (parcial) \u00a0 del art\u00edculo 42 del Decreto Ley 2591 de 1991,\u00a0\u201cpor \u00a0 el cual se reglamenta la acci\u00f3n de tutela consagrada en el art\u00edculo 86 de la \u00a0 Constituci\u00f3n Pol\u00edtica\u201d y al respecto se\u00f1al\u00f3: \u201cSon tres las hip\u00f3tesis \u00a0 previstas por el Constituyente respecto de la procedencia de la acci\u00f3n de tutela \u00a0 en el caso de acciones u omisiones de particulares, a saber: a) Cuando el \u00a0 particular presta un servicio p\u00fablico; b) Cuando la conducta del particular \u00a0 afecta grave y directamente el inter\u00e9s colectivo; y c) Cuando el solicitante se \u00a0 halle en estado de subordinaci\u00f3n o indefensi\u00f3n frente al particular.\u201d \u00a0 (Destaca la Sala). \u00a0 \u00a0<\/p>\n<p>[27] Ver sentencias T-1013 de 2006; T-584 de 2011 y T- 332 de \u00a0 2015, entre otras. \u00a0 \u00a0<\/p>\n<p>[28] Ver sentencia T- 488 de 2004. \u00a0 \u00a0<\/p>\n<p>[29] Ver T-030 de 2015. \u00a0 \u00a0<\/p>\n<p>[30] Ver T-733 de 2014. \u00a0 \u00a0<\/p>\n<p>\u00a0[31]Ver \u00a0 T-427 de 2015. \u00a0 \u00a0<\/p>\n<p>[32] \u00a0Ver T-316 de 2016. \u00a0 \u00a0<\/p>\n<p>[33] Ver sentencia T-947 de 2012. \u00a0 \u00a0<\/p>\n<p>[34] ART\u00cdCULO 134. TRASLADO.\u00a0 Se produce traslado \u00a0 cuando se provee un cargo con un funcionario o empleado que ocupa en propiedad \u00a0 otro de funciones afines, de la misma categor\u00eda y para el cual se exijan los \u00a0 mismos requisitos, aunque tengan distinta sede territorial. Nunca podr\u00e1 haber \u00a0 traslados entre las dos Salas de los Consejos Seccionales de la Judicatura. \u00a0 \u00a0<\/p>\n<p>Procede en los siguientes eventos: \u00a0 \u00a0<\/p>\n<p>1. Cuando el interesado lo solicite \u00a0 por razones de salud o seguridad debidamente comprobadas, que le hagan imposible \u00a0 continuar en el cargo o por estas mismas razones se encuentre afectado o \u00a0 afectada su c\u00f3nyuge, compa\u00f1era o compa\u00f1ero permanente, descendiente o \u00a0 ascendiente en primer grado de consanguinidad o \u00fanico civil, siempre que ello no \u00a0 implique condiciones menos favorables para el funcionario y medie su \u00a0 consentimiento expreso. \u00a0 \u00a0<\/p>\n<p>[35] Dicho Acuerdo derog\u00f3 el Acuerdo PSAA02-1581 de 2002. \u00a0 \u00a0<\/p>\n<p>[36] ART\u00cdCULO D\u00c9CIMO S\u00c9PTIMO. \u2013 T\u00e9rmino y \u00a0 Competencia para la solicitud de traslado: Los servidores judiciales en carrera, \u00a0 deber\u00e1n presentar por escrito, las correspondientes solicitudes de traslado como \u00a0 servidor de carrera, salud y razones del servicio, dentro de los primeros cinco \u00a0 (5) d\u00edas h\u00e1biles de cada mes, de acuerdo con las publicaciones de vacantes \u00a0 definitivas que efect\u00fae la Unidad de Administraci\u00f3n de la Carrera Judicial o las \u00a0 Salas Administrativas de los Consejos Seccionales seg\u00fan corresponda, a trav\u00e9s de \u00a0 la p\u00e1gina web de la Rama Judicial www.ramajudicial.gov.co. (\u2026) \u00a0 \u00a0<\/p>\n<p>Las solicitudes de traslado \u00a0 presentadas por Magistrados de Tribunal y Consejo Seccional con excepci\u00f3n de las \u00a0 de seguridad, deber\u00e1n dirigirse y presentarse en la Unidad de Administraci\u00f3n de \u00a0 la Carrera Judicial para el respectivo tr\u00e1mite y concepto ante la Sala \u00a0 Administrativa del Consejo Superior de la Judicatura. (\u2026). \u00a0 \u00a0<\/p>\n<p>[37] ART\u00cdCULO NOVENO. Concepto. Para efectos de emitir concepto sobre las \u00a0 peticiones de traslado por razones de salud, las Salas Administrativas de los \u00a0 Consejos Superior y Seccionales tendr\u00e1n en cuenta entre otros aspectos los \u00a0 siguientes: a) El diagn\u00f3stico m\u00e9dico sobre las condiciones de salud que se \u00a0 invocan, expedido en los t\u00e9rminos se\u00f1alados en el art\u00edculo octavo de este \u00a0 Acuerdo, en el cual se recomiende expresamente el traslado por la imposibilidad \u00a0 de continuar desempe\u00f1ando el cargo del cual es titular. Cuando se trate de la \u00a0 enfermedad del c\u00f3nyuge, compa\u00f1ero o compa\u00f1era permanente, descendiente o \u00a0 ascendiente en primer grado de consanguinidad o \u00fanico civil, el dictamen m\u00e9dico \u00a0 debe contener recomendaci\u00f3n clara y expresa que permita concluir a la \u00a0 Administraci\u00f3n, sobre la necesidad del traslado. b) Acreditaci\u00f3n del parentesco: \u00a0 Cuando se trate de enfermedad del c\u00f3nyuge, compa\u00f1ero o compa\u00f1era permanente, \u00a0 descendiente o ascendiente en primer grado de consanguinidad o \u00fanico civil. c) \u00a0 En el evento que la sede escogida no atienda la recomendaci\u00f3n m\u00e9dica, la Unidad \u00a0 de Carrera le ofrecer\u00e1 las vacantes existentes al momento, a efectos de obtener \u00a0 el consentimiento expreso del servidor. \u00a0 \u00a0<\/p>\n<p>[38] ART\u00cdCULO OCTAVO.- Requisitos: Los dict\u00e1menes m\u00e9dicos que reflejan \u00a0 las condiciones de salud (diagn\u00f3stico m\u00e9dico y recomendaciones de traslado), \u00a0 deber\u00e1n ser expedidos por la Entidad Promotora de Salud (EPS &#8211; IPS) o \u00a0 Administradora de Riesgos Profesionales (A.R.P) a la cual se encuentre afiliado \u00a0 el servidor. Cuando se trate de su c\u00f3nyuge, compa\u00f1ero o compa\u00f1era permanente, \u00a0 descendiente o ascendiente en primer grado de consanguinidad o \u00fanico civil, \u00a0 seg\u00fan corresponda, tambi\u00e9n se aceptar\u00e1 el dictamen m\u00e9dico que provenga del \u00a0 Sistema de Seguridad Social en Salud. Los dict\u00e1menes m\u00e9dicos no deber\u00e1n tener \u00a0 fecha de expedici\u00f3n superior a tres (3) meses. Igualmente, si el diagn\u00f3stico \u00a0 proviene de un m\u00e9dico particular \u00e9ste deber\u00e1 ser refrendado, por la EPS o por la \u00a0 Administradora de Riesgos Profesionales de la Rama Judicial cuando se trate de \u00a0 una enfermedad profesional del servidor. \u00a0 \u00a0<\/p>\n<p>[39] ART\u00cdCULO VIG\u00c9SIMO SEGUNDO. Remisi\u00f3n de conceptos e Informes a las \u00a0 autoridades nominadoras. Para la decisi\u00f3n definitiva de las solicitudes de \u00a0 traslado, se remitir\u00e1n a las respectivas autoridades nominadoras, los conceptos \u00a0 favorables conjuntamente con las Listas de Aspirantes por sede, si a ello \u00a0 hubiere lugar. Si la decisi\u00f3n es negativa, el concepto ser\u00e1 comunicado al \u00a0 interesado y para su conocimiento, al nominador del cargo de aspiraci\u00f3n de \u00a0 traslado correspondiente a trav\u00e9s de la Unidad de Carrera Judicial o Sala \u00a0 Administrativa Seccional seg\u00fan corresponda. \u00a0 \u00a0<\/p>\n<p>[40] ART\u00cdCULO VIG\u00c9SIMO TERCERO. Deberes de las autoridades nominadoras. \u00a0 En todos los casos las autoridades nominadoras deber\u00e1n informar a la Sala \u00a0 Administrativa del Consejo Superior \u2013 Unidad de Administraci\u00f3n de Carrera \u00a0 Judicial o Seccional de la Judicatura y a la Direcci\u00f3n Ejecutiva o Seccional \u00a0 seg\u00fan corresponda, de manera inmediata seg\u00fan la normatividad vigente, sobre la \u00a0 decisi\u00f3n del traslado o listas de elegibles seg\u00fan corresponda, para que se \u00a0 realicen las anotaciones respectivas y se ejerza el adecuado control de \u00a0 movimiento de personal. Con el informe, el nominador deber\u00e1 allegar copia del \u00a0 acto administrativo mediante el cual se resuelve la solicitud de traslado, e \u00a0 indicar\u00e1 la fecha de nombramiento y posesi\u00f3n de los servidores judiciales \u00a0 sujetos del traslado, a efectos de elaborar la actualizaci\u00f3n del Registro \u00a0 Nacional de Escalaf\u00f3n. El nominador deber\u00e1 tener en cuenta la evaluaci\u00f3n de los \u00a0 factores objetivos de antig\u00fcedad, la evaluaci\u00f3n de servicios y los resultados \u00a0 obtenidos en los concursos p\u00fablicos para el acceso a la Rama Judicial, al \u00a0 momento de evaluar las solicitudes de traslados de los servidores de carrera. \u00a0 \u00a0<\/p>\n<p>[41] Radicado No. \u00a0 11001-03-15-000-2018-00301-00(AC), C.P. Hernando S\u00e1nchez S\u00e1nchez. \u00a0 \u00a0<\/p>\n<p>[42] Secci\u00f3n Segunda, sentencia de tutela proferida el 25 de septiembre \u00a0 de 2017, radicado No. 08001-23-33-000-2017-00858-01(AC), C.P. William Hern\u00e1ndez \u00a0 G\u00f3mez. \u00a0 \u00a0<\/p>\n<p>[44] Sala de Casaci\u00f3n Penal, sentencia de tutela STP16140-2017. M.P. Eugenio Fern\u00e1ndez Carlier. \u00a0 \u00a0<\/p>\n<p>[45] Folios 120 \u2013 122 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[46] Folios 110 \u2013 111 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[47] Folios 112 \u2013 119 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[48] \u201c(\u2026) solicito se me informe: \u00a0 \u00a0<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Si, la Honorable Corte Suprema de Justicia adopt\u00f3 decisi\u00f3n alguna al respecto. \u00a0 \u00a0<\/p>\n<p>2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 En caso afirmativo, las razones objetivas que conllevaron a lo decidido. \u00a0 \u00a0<\/p>\n<p>3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Que funcionarios aspiramos al traslado de dicha vacante. \u00a0 \u00a0<\/p>\n<p>4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Si conjuntamente con la petici\u00f3n de traslado existi\u00f3 lista de aspirantes a \u00a0 traslado invocando motivos diferentes a la salud. \u00a0 \u00a0<\/p>\n<p>5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Que se informe si para dicha vacante existe registro de lista de elegibles. \u00a0 \u00a0<\/p>\n<p>6.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Quien ocupa en la actualidad dicho cargo y en qu\u00e9 calidad. (\u2026)\u201d. \u00a0 \u00a0<\/p>\n<p>[49] Las solicitudes que se refieran al \u00a0 ejercicio de las funciones jurisdiccionales de la Corte Suprema de Justicia son amparadas por los derechos \u00a0 fundamentales al debido proceso judicial (art\u00edculo 29 de la Constituci\u00f3n) y al acceso a la administraci\u00f3n de justicia o a la \u00a0 tutela judicial efectiva (art\u00edculo 229 de la Constituci\u00f3n). Dichas solicitudes \u00a0 dentro del tr\u00e1mite judicial no se encuentran amparadas \u00a0 por el derecho fundamental de petici\u00f3n (art\u00edculo 23 de la Constituci\u00f3n), ni su r\u00e9gimen jur\u00eddico es el establecido en la Ley \u00a0 Estatutaria del Derecho de Petici\u00f3n (Ley 1755 de 2015, incorporada al C\u00f3digo de \u00a0 Procedimiento Administrativo y de lo Contencioso Administrativo). \u00a0 \u00a0<\/p>\n<p>[50] Folios 53 \u2013 55 cuaderno principal. \u00a0 \u00a0<\/p>\n<p>[51] Cabe destacar que tal discusi\u00f3n fue zanjada a trav\u00e9s del art\u00edculo 24 \u00a0 del Acuerdo PCSJA17-10754 de 2017, rese\u00f1ado en l\u00edneas anteriores, pues en \u00e9l se \u00a0 determina que el cargo de magistrado de Sala \u00danica no tiene afinidad con ning\u00fan \u00a0 otro cargo de magistrado, distinto al de Sala \u00danica. \u00a0 \u00a0<\/p>\n<p>[52] \u201cART\u00cdCULO S\u00c9PTIMO.- los servidores judiciales en carrera, tienen \u00a0 derecho a ser traslados por razones de salud, debidamente comprobadas, a \u00a0 otro despacho judicial, cuando las mismas le hagan imposible continuar en el \u00a0 cargo o por \u00e9stas se encuentre afectado o afectada su c\u00f3nyuge, compa\u00f1ero o \u00a0 compa\u00f1era permanente, descendiente o ascendiente en primer grado de \u00a0 consanguinidad o \u00fanico civil\u201d \u00a0 (negrilla fuera del texto). \u00a0 \u00a0<\/p>\n<p>[53] Folio 127 cuaderno No. 1. \u00a0 \u00a0<\/p>\n<p>[54] Ver sentencia T-096 de 2018.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-302-19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 Sentencia T-302\/19 \u00a0 \u00a0 ACCION DE TUTELA CONTRA ACTO ADMINISTRATIVO QUE ORDENA O NIEGA \u00a0 TRASLADO DE SERVIDOR PUBLICO-Procedencia excepcional \u00a0 \u00a0 La \u00a0 jurisprudencia de la Corte Constitucional ha establecido, por regla general, que \u00a0 no procede la acci\u00f3n de tutela en contra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126],"tags":[],"class_list":["post-26786","post","type-post","status-publish","format-standard","hentry","category-tutelas-2019"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/26786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=26786"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/26786\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=26786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=26786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=26786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}