{"id":26915,"date":"2024-07-02T17:18:27","date_gmt":"2024-07-02T17:18:27","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/07\/02\/t-524-19\/"},"modified":"2024-07-02T17:18:27","modified_gmt":"2024-07-02T17:18:27","slug":"t-524-19","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-524-19\/","title":{"rendered":"T-524-19"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-524-19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia \u00a0 T-524\/19 \u00a0 \u00a0<\/p>\n<p>ACCION DE TUTELA PARA RECONOCIMIENTO DE \u00a0 PENSION DE SOBREVIVIENTES A HIJO EN SITUACION DE DISCAPACIDAD-Procedencia \u00a0 excepcional por ser el mecanismo id\u00f3neo \u00a0 \u00a0<\/p>\n<p>DERECHO A LA \u00a0 PENSION DE SOBREVIVIENTES PARA HIJO EN SITUACION DE DISCAPACIDAD-Requisitos \u00a0 \u00a0<\/p>\n<p>En el \u00a0 caso de la pensi\u00f3n de sobrevivientes para hijos en condici\u00f3n de discapacidad \u00a0 estos son: \u201c(i) la relaci\u00f3n filial; (ii) la situaci\u00f3n de discapacidad y que la \u00a0 misma hubiese generado perdida de la capacidad laboral \u00a0 igual o superior al 50%; y (iii) la dependencia econ\u00f3mica del hijo en situaci\u00f3n \u00a0 de discapacidad con el causante de la prestaci\u00f3n\u201d[53]; por lo que no puede \u00a0 exigirse un dictamen de p\u00e9rdida de capacidad laboral actualizado o con cierto rango de antig\u00fcedad como condici\u00f3n para \u00a0 estudiar una solicitud pensional. \u00a0 \u00a0<\/p>\n<p>DERECHO A LA PENSION DE SOBREVIVIENTES Y \u00a0 MINIMO VITAL-Vulneraci\u00f3n cuando entidades encargadas \u00a0 de reconocimiento exigen requisitos adicionales o distintos a los exigidos por la ley \u00a0 \u00a0<\/p>\n<p>Los \u00a0 fondos pensionales s\u00f3lo pueden solicitar aquellos documentos que sean necesarios \u00a0 e id\u00f3neos para acreditar los requisitos legales propios de cada prestaci\u00f3n \u00a0 social. \u00a0 \u00a0<\/p>\n<p>DERECHO A LA SUSTITUCION PENSIONAL \u00a0 DE HIJO EN SITUACION DE DISCAPACIDAD-Entidades encargadas de \u00a0 reconocimiento y pago no pueden exigir actualizaci\u00f3n del dictamen de p\u00e9rdida de \u00a0 capacidad laboral \u00a0 \u00a0<\/p>\n<p>DEBIDO PROCESO EN LA EXPEDICION DE LOS \u00a0 DICTAMENES DE PERDIDA DE LA CAPACIDAD LABORAL-Reglas \u00a0 \u00a0<\/p>\n<p>(i) El \u00a0 dictamen debe realizarse cuando las entidades \u00a0 correspondientes hayan comprobado la imposibilidad de rehabilitaci\u00f3n del \u00a0 paciente; (ii)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La valoraci\u00f3n que se \u00a0 realice debe ser completa e integral, de manera que se tengan en cuenta todos \u00a0 los aspectos m\u00e9dicos consignados en el historial m\u00e9dico \u00a0 del solicitante; (iii) La decisi\u00f3n adoptada tiene que ser debidamente motivada y \u00a0 justificar las razones f\u00e1cticas y jur\u00eddicas que soportan el dictamen, siempre \u00a0 con base en la historia cl\u00ednica y ocupacional del paciente y, (iv) La entidad \u00a0 correspondiente debe garantizar los derechos de defensa y contradicci\u00f3n de \u00a0 los solicitantes. \u00a0 \u00a0<\/p>\n<p>REGLAS BASICAS EN LA ACTUACION DE LAS \u00a0 JUNTAS DE CALIFICACION DE INVALIDEZ-Deben respetar el \u00a0 debido proceso \u00a0 \u00a0<\/p>\n<p>DERECHO A LA SUSTITUCION PENSIONAL DE HIJO \u00a0 EN SITUACION DE DISCAPACIDAD-Orden \u00a0 a Fondo de Pensiones estudiar \u00a0solicitud de reconocimiento, sin exigir dictamen de p\u00e9rdida de capacidad laboral \u00a0 actualizado \u00a0 \u00a0<\/p>\n<p>Referencia: Expediente T-7.327.896 \u00a0 \u00a0<\/p>\n<p>Acci\u00f3n de tutela formulada por Guillermo Calder\u00f3n, en calidad de agente \u00a0 oficioso de Blanca Patricia Goyeneche Calder\u00f3n, contra Medim\u00e1s EPS, el Fondo \u00a0 Territorial de Pensiones de Santander y la Junta Regional de Calificaci\u00f3n de \u00a0 Invalidez de Santander. \u00a0 \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0 \u00a0<\/p>\n<p>ALBERTO ROJAS R\u00cdOS \u00a0 \u00a0<\/p>\n<p>La Sala Novena de Revisi\u00f3n de la Corte Constitucional, \u00a0 integrada por la Magistrada Diana Fajardo Rivera y los Magistrados Carlos Bernal \u00a0 Pulido y Alberto Rojas R\u00edos, quien la preside, en ejercicio de sus competencias \u00a0 constitucionales y legales[1], profiere la siguiente: \u00a0 \u00a0<\/p>\n<p>SENTENCIA \u00a0 \u00a0<\/p>\n<p>En el proceso de \u00a0 revisi\u00f3n de los fallos del 17 de enero y el 26 de febrero de 2019, dictados por \u00a0 el Juzgado 68 Civil Municipal de Oralidad de Bogot\u00e1 D.C. y el Juzgado 21 Civil \u00a0 del Circuito de esa misma ciudad, en primera y segunda instancia, \u00a0 respectivamente, dentro de la acci\u00f3n de tutela promovida por el ciudadano \u00a0 Guillermo Calder\u00f3n, en calidad de agente oficioso de Blanca Patricia Goyeneche \u00a0 Calder\u00f3n en contra de Medim\u00e1s EPS, el Fondo Territorial de Pensiones de \u00a0 Santander y la Junta Regional de Calificaci\u00f3n de Invalidez de Santander. \u00a0 \u00a0<\/p>\n<p>El proceso de la \u00a0 referencia fue escogido por la Sala de Selecci\u00f3n de Tutelas N\u00famero Cinco, \u00a0 mediante Auto proferido el 21 de mayo de 2019, bajo el criterio subjetivo: \u00a0 urgencia de proteger un derecho fundamental y criterio objetivo: posible \u00a0 violaci\u00f3n o desconocimiento de un precedente de la Corte Constitucional[2]. \u00a0 \u00a0<\/p>\n<p>I.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 ANTECEDENTES \u00a0 \u00a0<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Hechos \u00a0 \u00a0<\/p>\n<p>1.1.\u00a0\u00a0\u00a0 \u00a0 El se\u00f1or Guillermo Calder\u00f3n es hermano de Blanca Patricia Goyeneche Calder\u00f3n, \u00a0 quien tiene 62 a\u00f1os de edad y fue diagnosticada con trastorno psic\u00f3tico \u00a0 cr\u00f3nico y epilepsia desde 1989[3], enfermedades de car\u00e1cter \u201ccr\u00f3nico, \u00a0 progresivo y deteriorante\u201d[4]. \u00a0 Como consecuencia de estas afecciones su p\u00e9rdida de capacidad laboral fue \u00a0 valorada en dos oportunidades: (i) El 8 de octubre de 2001, CAPRECOM estableci\u00f3 \u00a0 que ten\u00eda un porcentaje de p\u00e9rdida del 52.9%, pero no refiri\u00f3 una fecha de \u00a0 estructuraci\u00f3n[5]; y, (ii) El 30 de abril de 2003, la \u00a0 Junta Regional de Calificaci\u00f3n de Invalidez de Santander determin\u00f3 un 70% con \u00a0 fecha de estructuraci\u00f3n del 4 de septiembre de 2001[6]. \u00a0 \u00a0<\/p>\n<p>1.2.\u00a0\u00a0\u00a0 \u00a0 La se\u00f1ora Blanca Patricia Goyeneche depend\u00eda econ\u00f3micamente de su madre[7], Elvia \u00a0 Calder\u00f3n de Goyeneche, quien recib\u00eda una pensi\u00f3n mensual de jubilaci\u00f3n por parte \u00a0 del Instituto del Seguro Social de Santander[8], \u00a0 hoy a cargo del Fondo Territorial de Pensiones de la Gobernaci\u00f3n de Santander. \u00a0 \u00a0\u00a0<\/p>\n<p>1.3.\u00a0\u00a0\u00a0 \u00a0 El 20 de mayo de 2018, la se\u00f1ora Elvia Calder\u00f3n de Goyeneche falleci\u00f3[9]. \u00a0 El 27 de julio de esa misma anualidad, el se\u00f1or Guillermo Calder\u00f3n solicit\u00f3 el \u00a0 reconocimiento de la pensi\u00f3n de sobrevivientes en favor de su hermana[10]. \u00a0 \u00a0<\/p>\n<p>1.4.\u00a0\u00a0\u00a0 A trav\u00e9s de \u00a0 oficio de fecha 31 de julio de 2018, el Fondo Territorial de Pensiones de \u00a0 Santander indic\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cEs necesario la actualizaci\u00f3n del certificado de \u00a0 calificaci\u00f3n de invalidez expedido por la Junta de Calificaci\u00f3n de Invalidez, \u00a0 con una fecha de expedici\u00f3n no mayor a 3 a\u00f1os, dado que el certificado allegado \u00a0 tiene una fecha de expedici\u00f3n del 30 de abril de 2003; este documento est\u00e1 \u00a0 establecido como requisito indispensable con el fin de determinar el porcentaje \u00a0 actual y la fecha de estructuraci\u00f3n de invalidez, tal como lo contempla el \u00a0 art\u00edculo 41 de la ley 100 de 1993 modificado por el art\u00edculo 52 de la ley 962 de \u00a0 2005 a su vez modificado por el art\u00edculo 142 del decreto 019 de 2012 (\u2026)\u201d [11].\u00a0 \u00a0 \u00a0<\/p>\n<p>1.5.\u00a0\u00a0\u00a0 \u00a0 Debido a tal negativa, la agenciada solicit\u00f3 una nueva calificaci\u00f3n a la EPS \u00a0 Medim\u00e1s, la cual emiti\u00f3 dictamen No. 14078632 del 27 de septiembre de 2018 \u00a0 ratificando que la se\u00f1ora Blanca Patricia tiene un porcentaje de p\u00e9rdida de \u00a0 capacidad laboral del 70% y determin\u00f3 que la fecha de estructuraci\u00f3n \u00a0 correspond\u00eda al mismo d\u00eda en que se realiz\u00f3 la calificaci\u00f3n, textualmente el \u00a0 dictamen refiere: \u201cse establece como fecha de estructuraci\u00f3n corresponde a la \u00a0 fecha de la presente calificaci\u00f3n 26\/09\/2018 (sic)\u201d[12]. \u00a0 \u00a0<\/p>\n<p>1.6.\u00a0\u00a0\u00a0 \u00a0 El se\u00f1or Guillermo Calder\u00f3n afirm\u00f3 que acudi\u00f3 con dicho dictamen a las \u00a0 instalaciones del Fondo Territorial de Pensiones, donde le informaron que deb\u00eda \u00a0 interponer los recursos pertinentes contra \u00e9ste para controvertir la fecha de \u00a0 estructuraci\u00f3n. Lo anterior, debido a que constituye un obst\u00e1culo para el \u00a0 reconocimiento pensional, por cuanto indica que el estado de invalidez se \u00a0 configur\u00f3 con posterioridad al fallecimiento de la se\u00f1ora Elvia Calder\u00f3n. En \u00a0 consecuencia, el 4 de octubre de 2018 se formul\u00f3 recurso de reposici\u00f3n y en \u00a0 subsidio apelaci\u00f3n, al considerar errada la fecha de estructuraci\u00f3n de invalidez \u00a0 por cuanto no corresponder\u00eda a los hechos de la historia cl\u00ednica[13]. \u00a0 \u00a0<\/p>\n<p>1.7.\u00a0\u00a0\u00a0 \u00a0 Al no recibir respuesta por parte de Medim\u00e1s EPS, el 13 de diciembre de 2018 el \u00a0 se\u00f1or Guillermo Calder\u00f3n formul\u00f3 acci\u00f3n de tutela contra las entidades \u00a0 involucradas, en calidad de agente oficioso de su hermana, indicando que: (i) \u00a0 ella se encuentra en una grave situaci\u00f3n econ\u00f3mica y de salud al quedar \u00a0 desafiliada del Sistema de Seguridad Social con posterioridad al fallecimiento \u00a0 de su madre; y, (ii) le ha sido imposible acceder a la pensi\u00f3n de sobrevivientes \u00a0 que solicit\u00f3 desde el 27 de julio de 2018. \u00a0 \u00a0<\/p>\n<p>Por \u00a0 lo cual, solicit\u00f3: (i) el amparo de sus derechos fundamentales a la vida, a la \u00a0 integridad, a la salud, a la seguridad social, al m\u00ednimo vital y de petici\u00f3n; y, \u00a0 (ii) el reconocimiento de la pensi\u00f3n de sobrevivientes en calidad de hija en \u00a0 condici\u00f3n de invalidez[14]. \u00a0 \u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>2. Tr\u00e1mite de la acci\u00f3n de tutela \u00a0 \u00a0<\/p>\n<p>2.1.\u00a0\u00a0\u00a0 \u00a0 El Juzgado 68 Civil Municipal de Oralidad de Bogot\u00e1 D.C., admiti\u00f3 la acci\u00f3n de \u00a0 tutela el 14 de diciembre de 2018, notific\u00f3 a las autoridades accionadas y \u00a0 vincul\u00f3 al tr\u00e1mite a la Secretar\u00eda Distrital de Salud de Bogot\u00e1 D.C, a la \u00a0 Administradora de los Recursos del Sistema General de Seguridad Social en Salud \u00a0 \u2013ADRES\u2013, al Hospital Psiqui\u00e1trico San Camilo de Bucaramanga, al Instituto del \u00a0 Seguro Social de Santander, a Caprecom en liquidaci\u00f3n, al Ministerio de Salud y \u00a0 Protecci\u00f3n Social y a Golden Group EPS[15]. \u00a0 \u00a0<\/p>\n<p>Se \u00a0 presentaron las siguientes intervenciones: \u00a0 \u00a0<\/p>\n<p>a.\u00a0\u00a0\u00a0\u00a0 Fondo Territorial de Pensiones de Santander \u00a0 \u00a0<\/p>\n<p>Mediante escrito de 17 de diciembre de 2018 solicit\u00f3 declarar improcedente la \u00a0 acci\u00f3n, por cuanto no hab\u00eda vulnerado los derechos fundamentales de la se\u00f1ora \u00a0 Blanca Patricia Goyeneche, en tanto debe aportar la calificaci\u00f3n de p\u00e9rdida de \u00a0 capacidad laboral actualizada. Al respecto, sostuvo: \u00a0 \u00a0<\/p>\n<p>\u201cUna vez analizada la documentaci\u00f3n aportada para el \u00a0 tr\u00e1mite de solicitud de pensi\u00f3n de sobreviviente, se evidencia que est\u00e1 \u00a0 incompleta por lo cual este despacho a trav\u00e9s del proceso con radicado \u00a0 20180130036 de 31 de julio de 2018 acusa recibo de la petici\u00f3n y solicita el \u00a0 certificado de calificaci\u00f3n de p\u00e9rdida de la capacidad laboral, expedido por la \u00a0 Junta de Calificaci\u00f3n de Invalidez, o entidad competente, con una fecha de \u00a0 expedici\u00f3n no mayor a 3 a\u00f1os, dado que el certificado allegado tiene una \u00a0 fecha de expedici\u00f3n del 30 de abril de 2003; este documento est\u00e1 establecido \u00a0 como requisito indispensable con el fin de determinar el porcentaje actual y la \u00a0 fecha de estructuraci\u00f3n de invalidez, tal como lo contempla el art\u00edculo 41 de la \u00a0 ley 100 de 1993 modificado por el art\u00edculo 52 de la ley 962 de 2005 a su vez \u00a0 modificado por el art\u00edculo 142 del decreto 019 de 2012\u201d[16]. \u00a0 \u00a0<\/p>\n<p>b.\u00a0\u00a0\u00a0 Junta Regional de Calificaci\u00f3n de Invalidez \u00a0 de Santander \u00a0 \u00a0<\/p>\n<p>A \u00a0 trav\u00e9s de correo electr\u00f3nico enviado el 19 de diciembre de 2018, la Directora \u00a0 Administrativa y Financiera de esa entidad solicit\u00f3 ser desvinculada del tr\u00e1mite \u00a0 de la presente acci\u00f3n, en raz\u00f3n a que las pretensiones van dirigidas a otra \u00a0 entidad y las mismas deber\u00e1n ser resueltas en su momento por el juez de tutela[17]. \u00a0 \u00a0<\/p>\n<p>c.\u00a0\u00a0\u00a0\u00a0\u00a0 Secretaria Distrital de Salud de Bogot\u00e1 D.C. \u00a0 \u00a0<\/p>\n<p>Por medio de \u00a0 escrito radicado el 18 de diciembre de 2018, manifest\u00f3 que no se encontraba \u00a0 legitimada por pasiva, dado que dentro de sus competencias no se encuentra dar \u00a0 soluci\u00f3n al problema que se aborda. A su vez, indic\u00f3 que este no es el mecanismo \u00a0 judicial para resolver las pretensiones incoadas por la parte actora[18]. \u00a0 \u00a0<\/p>\n<p>d.\u00a0\u00a0\u00a0 \u00a0Ministerio de \u00a0 Salud y Protecci\u00f3n Social \u00a0 \u00a0<\/p>\n<p>A trav\u00e9s de correo \u00a0 electr\u00f3nico enviado el 18 de diciembre de 2018, la Directora Jur\u00eddica del \u00a0 Ministerio de Salud y Protecci\u00f3n Social solicit\u00f3 declarar la improcedencia del \u00a0 amparo y tambi\u00e9n su exoneraci\u00f3n de cualquier responsabilidad por falta de \u00a0 legitimaci\u00f3n en la causa por pasiva, toda vez que no es el encargado de realizar \u00a0 las actuaciones administrativas tendientes a resolver la pretensi\u00f3n de la \u00a0 accionante[19]. \u00a0 \u00a0<\/p>\n<p>e.\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Hospital \u00a0 Psiqui\u00e1trico San Camilo de Bucaramanga \u00a0 \u00a0<\/p>\n<p>Por medio de correo \u00a0 electr\u00f3nico enviado el 26 de diciembre de 2018, la Representante Legal del \u00a0 hospital manifest\u00f3 que \u00e9ste no ten\u00eda legitimaci\u00f3n en la causa por pasiva \u00a0 argumentando que no guarda registro f\u00edsico ni digital de la historia cl\u00ednica de \u00a0 la se\u00f1ora Blanca Patricia Goyeneche Calder\u00f3n[20]. \u00a0 \u00a0<\/p>\n<p>f.\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Administradora de \u00a0 los Recursos del Sistema General de Seguridad Social en Salud \u2013ADRES\u2013 \u00a0 \u00a0<\/p>\n<p>Mediante correo \u00a0 electr\u00f3nico enviado el 19 de diciembre de 2018, el jefe de la Oficina Jur\u00eddica \u00a0 de la mencionada instituci\u00f3n tambi\u00e9n solicit\u00f3 que se declarara su falta de \u00a0 legitimaci\u00f3n en la causa por pasiva, en raz\u00f3n a que no es la llamada a dirimir \u00a0 los conflictos de car\u00e1cter pensional y\/o laboral[21]. \u00a0 \u00a0<\/p>\n<p>g.\u00a0\u00a0\u00a0\u00a0 \u00a0Medim\u00e1s EPS \u00a0 \u00a0<\/p>\n<p>Esta entidad guard\u00f3 \u00a0 silencio y no remiti\u00f3 ninguna contestaci\u00f3n a la acci\u00f3n de tutela bajo estudio. \u00a0 \u00a0<\/p>\n<p>3. Sentencia de \u00a0 primera instancia \u00a0 \u00a0<\/p>\n<p>El 17 de enero de \u00a0 2019, el Juzgado 68 Civil Municipal de Oralidad de Bogot\u00e1 D.C., neg\u00f3 el amparo \u00a0 invocado al considerar que la parte actora no cumpli\u00f3 con el requisito de \u00a0 subsidiariedad, dada la existencia de otros mecanismos de defensa judicial ante \u00a0 la jurisdicci\u00f3n ordinaria laboral. As\u00ed mismo, orden\u00f3 desvincular de la presente \u00a0 acci\u00f3n constitucional a la Secretar\u00eda Distrital de Salud de Bogot\u00e1 D.C., al \u00a0 Ministerio de Salud y Protecci\u00f3n Social, a la Administradora de los Recursos del \u00a0 Sistema General de Seguridad Social en Salud \u2013ADRES\u2013, al Hospital Psiqui\u00e1trico \u00a0 San Camilo de Bucaramanga, a Caprecom en liquidaci\u00f3n y a Golden Group EPS[22]. \u00a0 \u00a0<\/p>\n<p>4. Impugnaci\u00f3n \u00a0 \u00a0<\/p>\n<p>En escrito del 23 \u00a0 de enero de 2019, la parte actora impugn\u00f3 el fallo de primera instancia. \u00a0 Argument\u00f3 que el juez no tuvo en cuenta el estado de salud de la accionante ni \u00a0 la especial protecci\u00f3n que le brinda la Constituci\u00f3n e ignor\u00f3 que Medim\u00e1s EPS \u00a0 guard\u00f3 silencio frente a los hechos y pretensiones de la presente acci\u00f3n de \u00a0 tutela. Por otra parte, indic\u00f3 que no es cierto que no se hayan agotado los \u00a0 recursos de ley o medios de defensa ordinarios para acceder al amparo de sus \u00a0 derechos, pues interpuso recurso de reposici\u00f3n y en subsidio apelaci\u00f3n contra el \u00a0 dictamen emitido el 27 de septiembre de 2018, sin que a la fecha haya sido \u00a0 resuelto[23]. \u00a0 \u00a0<\/p>\n<p>5. Sentencia de \u00a0 segunda instancia \u00a0 \u00a0<\/p>\n<p>En fallo de segunda \u00a0 instancia del 26 de febrero de 2019, el Juzgado 21 Civil del Circuito de Bogot\u00e1 \u00a0 D.C., confirm\u00f3 la sentencia de primera instancia. El fallador estim\u00f3 que al \u00a0 estar pendiente la resoluci\u00f3n del recurso de reposici\u00f3n y en subsidio apelaci\u00f3n \u00a0 interpuesto por la accionante, resultaba improcedente la acci\u00f3n de tutela, \u00a0 m\u00e1xime cuando la decisi\u00f3n que adopte la EPS accionada puede ser controvertida[24]. \u00a0 \u00a0<\/p>\n<p>6. Material \u00a0 probatorio obrante en el expediente[25] \u00a0 \u00a0<\/p>\n<p>-Copia de las \u00a0 c\u00e9dulas de ciudadan\u00eda de Guillermo Calder\u00f3n, Blanca Patricia Goyeneche Calder\u00f3n \u00a0 y Elvia Calder\u00f3n de Goyeneche[26]. \u00a0 \u00a0<\/p>\n<p>-Copia del registro \u00a0 civil de nacimiento de Blanca Patricia Goyeneche Calder\u00f3n, en el que se registra \u00a0 que su progenitora es Elvia Calder\u00f3n[27]. \u00a0 \u00a0<\/p>\n<p>-Copia de la \u00a0 Resoluci\u00f3n J-154 del 1\u00b0 de febrero de 1982 mediante la cual reconoci\u00f3 pensi\u00f3n de \u00a0 vejez a la se\u00f1ora Elvia Calder\u00f3n de Goyeneche[28]. \u00a0 \u00a0<\/p>\n<p>-Copia del \u00a0 certificado emitido el 20 de enero de 1989 por el m\u00e9dico tratante de Blanca \u00a0 Patricia Goyeneche del Hospital Psiqui\u00e1trico San Camilo de Bucaramanga, en el \u00a0 que se certifica que desde hace varios a\u00f1os ha atendido a la accionante quien \u201cpresenta \u00a0 trastorno psic\u00f3tico cr\u00f3nico y epilepsia\u201d[29]. \u00a0 \u00a0<\/p>\n<p>-Copia de la \u00a0 petici\u00f3n presentada por la se\u00f1ora Elvia Calder\u00f3n el 12 de marzo de 2018, en el \u00a0 que solicita al M\u00e9dico Jefe del Seguro Departamental que, despu\u00e9s de su \u00a0 fallecimiento, traslade su pensi\u00f3n de jubilaci\u00f3n a su hija Blanca Patricia \u00a0 Goyeneche, debido a la disminuci\u00f3n de su capacidad laboral[30]. \u00a0 \u00a0<\/p>\n<p>-Copia del Acuerdo \u00a0 No. II de la Junta Directiva del Instituto del Seguro Social de Santander \u00a0 aprobado el 26 de julio de 1991, mediante el cual autoriza atenci\u00f3n m\u00e9dica a la \u00a0 se\u00f1ora Blanca Patricia Goyeneche Calder\u00f3n en condici\u00f3n de hija con discapacidad[31]. \u00a0 \u00a0<\/p>\n<p>-Copia del dictamen \u00a0 emitido por Caprecom de fecha 8 de octubre de 2001, en el que se establece la \u00a0 p\u00e9rdida de capacidad laboral en 52,9% ante el diagn\u00f3stico de \u201cretraso mental \u00a0 moderado, s\u00edndrome epil\u00e9ptico focal y trastorno psic\u00f3tico cr\u00f3nico\u201d. No se \u00a0 registra ning\u00fan antecedente laboral y se indica lo siguiente: \u201cmanifiesta que \u00a0 nunca ha trabajado\u201d[32]. \u00a0 \u00a0<\/p>\n<p>-Copia del dictamen \u00a0 emitido por la Junta Regional de Calificaci\u00f3n de Invalidez el 30 de abril de \u00a0 2003, en el que establece que la accionante tiene una p\u00e9rdida de capacidad \u00a0 laboral del 70% con fecha de estructuraci\u00f3n del 7 de septiembre de 2001, bajo el \u00a0 diagn\u00f3stico de trastorno psic\u00f3tico y s\u00edndrome compulsivo. As\u00ed mismo, se \u00a0 registra que no tiene antecedentes laborales y se encuentra inactiva \u00a0 econ\u00f3micamente[33]. \u00a0 \u00a0<\/p>\n<p>-Certificado de la \u00a0 Directora Administrativa y Financiera de la Junta Regional de Calificaci\u00f3n de \u00a0 Invalidez de Santander, en el que hace constar que el dictamen realizado el 30 \u00a0 de abril de 2003 se encuentra en firme[34]. \u00a0 \u00a0<\/p>\n<p>-Copia del registro \u00a0 de defunci\u00f3n de Elvia Calder\u00f3n de Goyeneche, quien falleci\u00f3 el 20 de mayo de \u00a0 2018[35]. \u00a0 \u00a0<\/p>\n<p>-Copia del Dictamen \u00a0 No. 14078362 de fecha 27 de septiembre de 2018, realizado por Medim\u00e1s EPS, en el \u00a0 que no se registra ning\u00fan antecedente laboral y se establecen como enfermedades \u00a0 de la actora \u201cretraso del desarrollo, psicosis asociado [y] \u00a0s\u00edndrome convulsivo\u201d, lo que dio lugar a un 70% de p\u00e9rdida de capacidad \u00a0 laboral con fecha de estructuraci\u00f3n el 26 de septiembre de 2018[36]. \u00a0 \u00a0<\/p>\n<p>-Copia del recurso \u00a0 de reposici\u00f3n y en subsidio apelaci\u00f3n interpuesto ante Medim\u00e1s EPS el 4 de \u00a0 octubre de 2018 solicitando modificaci\u00f3n a la fecha de estructuraci\u00f3n de \u00a0 invalidez[37]. \u00a0 \u00a0<\/p>\n<p>-Copia de \u00a0 prescripci\u00f3n m\u00e9dica del 29 de noviembre de 2018, en el que la Cl\u00ednica Retornar \u00a0 S.A.S detalla que la se\u00f1ora Blanca Patricia Goyeneche \u201cpadece trastorno \u00a0 psic\u00f3tico secundario a epilepsia y retraso mental leve. Enfermedades estas de \u00a0 car\u00e1cter cr\u00f3nico, progresivo y deteriorante. Por esta raz\u00f3n no est\u00e1 en capacidad \u00a0 de autodeterminarse y ha perdido la capacidad funcional certificado por medicina \u00a0 laboral\u201d[38]. \u00a0 \u00a0<\/p>\n<p>7. Actuaciones \u00a0 surtidas en sede de revisi\u00f3n \u00a0 \u00a0<\/p>\n<p>a. Documentos \u00a0 allegados por el agente oficioso \u00a0 \u00a0<\/p>\n<p>El 11 de julio de \u00a0 2019, el se\u00f1or Guillermo Calder\u00f3n aport\u00f3 varios documentos a esta Corporaci\u00f3n en \u00a0 los cuales indic\u00f3 que interpuso otra acci\u00f3n de tutela con una pretensi\u00f3n \u00a0 diferente dirigida a solicitar el amparo del derecho fundamental de petici\u00f3n, en \u00a0 tanto Medim\u00e1s EPS a\u00fan no ha contestado el recurso interpuesto. \u00a0 \u00a0<\/p>\n<p>Esta acci\u00f3n fue \u00a0 concedida por el Juzgado 30 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas \u00a0 de Bogot\u00e1 D.C., mediante fallo del 7 de junio de 2019, en el que se orden\u00f3 a \u00a0 Medim\u00e1s EPS que \u201crealice las gestiones pertinentes tendientes a darle tr\u00e1mite \u00a0 a los recursos interpuestos (\u2026) y si es procedente remita el correspondiente \u00a0 expediente ante la JUNTA REGIONAL DE CALIFICACI\u00d3N, que sea competente para este \u00a0 caso\u201d. Sin embargo, el se\u00f1or Calder\u00f3n se\u00f1al\u00f3 que a\u00fan no se ha dado tr\u00e1mite a \u00a0 su recurso ni se ha enviado a la respectiva Junta de Calificaci\u00f3n[39]. \u00a0 \u00a0<\/p>\n<p>b. Auto del \u00a0 1\u00ba de agosto de 2019 \u00a0 \u00a0<\/p>\n<p>El Magistrado \u00a0 Ponente mediante Auto corri\u00f3 traslado y puso a disposici\u00f3n de Medim\u00e1s EPS, el \u00a0 Fondo Territorial de Pensiones de Santander y la Junta Regional de Calificaci\u00f3n \u00a0 de Invalidez de Santander, los documentos allegados al proceso por el \u00a0 accionante, para que se pronunciaran sobre el asunto objeto de estudio. \u00a0 \u00a0<\/p>\n<p>c. Fondo Territorial de \u00a0 Pensiones de Santander[40] \u00a0 \u00a0<\/p>\n<p>Reiter\u00f3 respecto de la solicitud de reconocimiento de la pensi\u00f3n de \u00a0 sobrevivientes bajo estudio, que una vez analizada la documentaci\u00f3n aportada\u00a0 \u00a0 por la accionante, se evidenci\u00f3 que estaba incompleta, toda vez que no aport\u00f3 un \u00a0 certificado de calificaci\u00f3n de la perdida de la capacidad laboral \u201ccon una \u00a0 fecha de expedici\u00f3n no mayor de 3 a\u00f1os\u201d[41]. \u00a0 \u00a0<\/p>\n<p>Indic\u00f3 que es Medim\u00e1s EPS \u00a0 quien est\u00e1 vulnerando los derechos fundamentales a la se\u00f1ora Blanca Patricia \u00a0 Goyeneche, por cuanto no ha remitido los documentos a la Junta Regional de \u00a0 Calificaci\u00f3n de Invalidez para que se dirima el conflicto relativo a la fecha de \u00a0 estructuraci\u00f3n. \u00a0 \u00a0<\/p>\n<p>d. Junta \u00a0 Regional de Calificaci\u00f3n de Invalidez de Santander[42] \u00a0 \u00a0<\/p>\n<p>Expuso que no le \u00a0 constan los hechos descritos por la accionante, de tal manera, que la acci\u00f3n de \u00a0 tutela no va dirigida contra dicha entidad. Adem\u00e1s, se\u00f1al\u00f3 desde el 30 de abril \u00a0 de 2003 emiti\u00f3 el dictamen No. 403, en donde estableci\u00f3 que la accionante ten\u00eda \u00a0 un 70% de p\u00e9rdida de capacidad laboral, con fecha de estructuraci\u00f3n del 4 de \u00a0 septiembre de 2001. \u00a0 \u00a0<\/p>\n<p>e. Medim\u00e1s \u00a0 EPS \u00a0 \u00a0<\/p>\n<p>Esta entidad sigui\u00f3 \u00a0 sin realizar alguna intervenci\u00f3n dentro del proceso. \u00a0 \u00a0<\/p>\n<p>II. \u00a0 CONSIDERACIONES \u00a0 \u00a0<\/p>\n<p>1. Competencia \u00a0 \u00a0<\/p>\n<p>Esta Sala de \u00a0 Revisi\u00f3n de la Corte Constitucional es competente para conocer los fallos \u00a0 proferidos dentro de las acciones de tutela de la referencia, con fundamento en \u00a0 lo dispuesto en los art\u00edculos 86, inciso 3\u00b0, y 241, numeral 9\u00b0, de la \u00a0 Constituci\u00f3n Pol\u00edtica, en concordancia con los art\u00edculos 33, 34, 35 y 36 del \u00a0 Decreto 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>2. Examen de \u00a0 procedencia formal de la acci\u00f3n de tutela \u00a0 \u00a0<\/p>\n<p>En \u00a0 primer lugar, la Sala determinar\u00e1 si la acci\u00f3n de amparo cumple con los \u00a0 requisitos formales de procedencia: (i) legitimaci\u00f3n en la causa por activa; \u00a0 (ii) legitimaci\u00f3n en la causa por pasiva; (iii) inmediatez; y, (iv) \u00a0 subsidiariedad. Para ello, se reiterar\u00e1n las reglas jur\u00eddicas en la materia y se \u00a0 verificar\u00e1 el cumplimiento de cada uno de los presupuestos indicados. De \u00a0 resultar procedente la acci\u00f3n, la Sala abordar\u00e1 el respectivo examen de fondo. \u00a0 \u00a0<\/p>\n<p>2.1 Legitimaci\u00f3n \u00a0 en la causa por activa \u00a0 \u00a0<\/p>\n<p>El art\u00edculo 86 de \u00a0 la Constituci\u00f3n dispone que el amparo puede ser ejercido en todo momento y lugar \u00a0 por cualquier persona que estime vulnerados o amenazados sus derechos \u00a0 fundamentales, quien a su vez podr\u00e1 actuar por s\u00ed misma o por intermedio de \u00a0 representante[43]. \u00a0 La 10\u00aa disposici\u00f3n\u00a0 del Decreto 2591 de 1991, en su inciso segundo \u00a0 establece que: \u201ctambi\u00e9n se pueden agenciar derechos ajenos cuando el titular \u00a0 de los mismos no est\u00e9 en condiciones de promover su propia defensa. Cuando tal \u00a0 circunstancia ocurra, deber\u00e1 manifestarse en la solicitud\u201d[44]. \u00a0 \u00a0<\/p>\n<p>Esta Corporaci\u00f3n ha \u00a0 se\u00f1alado que los requisitos de la agencia oficiosa son los siguientes: i) \u00a0 la manifestaci\u00f3n del agente de actuar como tal; y, ii) la imposibilidad del \u00a0 titular del derecho fundamental para promover su propia defensa[45]. \u00a0 \u00a0<\/p>\n<p>En el caso bajo \u00a0 estudio, se observa que la acci\u00f3n de tutela fue interpuesta por el se\u00f1or \u00a0 Guillermo Calder\u00f3n, quien manifiesta actuar como agente oficioso de su hermana, \u00a0 Blanca Patricia Goyeneche Calder\u00f3n, debido a que ella se encuentra en condici\u00f3n \u00a0 de discapacidad. \u00a0 \u00a0<\/p>\n<p>La Corte evidencia \u00a0 que la agenciada tiene 62 a\u00f1os y fue diagnosticada con trastorno psic\u00f3tico \u00a0 cr\u00f3nico y epilepsia, lo que le ha generado una p\u00e9rdida de capacidad laboral \u00a0 del 70%, en consecuencia, no se encuentra en condiciones de promover su propia \u00a0 defensa. \u00a0 \u00a0<\/p>\n<p>De tal forma, se \u00a0 cumplen los dos requisitos previstos para aplicar la figura de la agencia \u00a0 oficiosa y, por ende, se acredita la legitimaci\u00f3n por activa de Guillermo \u00a0 Calder\u00f3n para formular la presente acci\u00f3n en favor de las garant\u00edas \u00a0 constitucionales de su hermana. \u00a0 \u00a0<\/p>\n<p>2.2 Legitimaci\u00f3n \u00a0 en la causa por pasiva \u00a0 \u00a0<\/p>\n<p>Los art\u00edculos 5\u00ba y 13 del Decreto 2591 de \u00a0 1991 se\u00f1alan que la acci\u00f3n debe dirigirse contra la autoridad p\u00fablica o el \u00a0 representante del \u00f3rgano que presuntamente haya violado o amenazado los derechos \u00a0 fundamentales del demandante. A su vez, las disposiciones 86 Superior y 42 del \u00a0 Decreto en cita establecen las condiciones para que el amparo pueda formularse \u00a0 contra acciones u omisiones de particulares[46]. \u00a0 \u00a0<\/p>\n<p>En \u00a0 el caso de la referencia, la legitimaci\u00f3n del Fondo Territorial de Pensiones de \u00a0 Santander se encuentra acreditada, en tanto se trata de la autoridad p\u00fablica que \u00a0 neg\u00f3 la solicitud pensional de la agenciada. En lo que respecta a la Junta \u00a0 Regional de Calificaci\u00f3n de Invalidez de Santander[47] \u00a0y Medim\u00e1s EPS, la Sala destaca que tambi\u00e9n se cumple este requisito toda vez que \u00a0 se trata de entidades particulares que prestan un servicio p\u00fablico, como lo es \u00a0 el de seguridad social y salud[48], adem\u00e1s, sus actuaciones se relacionan \u00a0 directamente con la expedici\u00f3n de los dict\u00e1menes de p\u00e9rdida de capacidad laboral \u00a0 de la se\u00f1ora Blanca Patricia Goyeneche. \u00a0 \u00a0<\/p>\n<p>2.3 Inmediatez \u00a0 \u00a0<\/p>\n<p>La \u00a0 acci\u00f3n de tutela tiene como prop\u00f3sito proveer a los ciudadanos un instrumento \u00a0 jur\u00eddico para hacer frente a la amenaza grave e inminente de sus \u00a0 derechos fundamentales, por lo que la procedibilidad del amparo est\u00e1 sujeta a \u00a0 que se haya formulado en un tiempo razonable respecto al acto que \u00a0 presuntamente vulnera sus garant\u00edas[49]. \u00a0 \u00a0<\/p>\n<p>En \u00a0 el asunto bajo estudio, la Sala encuentra que Medim\u00e1s EPS profiri\u00f3 su dictamen \u00a0 de p\u00e9rdida de capacidad laboral el 27 de septiembre de 2018 y el 4 de octubre de \u00a0 esa misma anualidad se formul\u00f3 el recurso de reposici\u00f3n y en subsidio apelaci\u00f3n \u00a0 en su contra, sin que hasta el momento se haya obtenido respuesta alguna por \u00a0 parte de la EPS. \u00a0 \u00a0<\/p>\n<p>Esta \u00a0 situaci\u00f3n motiv\u00f3 la formulaci\u00f3n del presente amparo el d\u00eda 13 de diciembre de \u00a0 2018, es decir, tan s\u00f3lo un poco m\u00e1s de dos meses despu\u00e9s de la presentaci\u00f3n del \u00a0 recurso, lo que permite concluir que el amparo se formul\u00f3 en un tiempo \u00a0 razonable, en consecuencia, se cumple con el presupuesto de inmediatez. \u00a0 \u00a0<\/p>\n<p>2.4 Subsidiariedad \u00a0 \u00a0<\/p>\n<p>El art\u00edculo 86 de \u00a0 la Constituci\u00f3n Pol\u00edtica establece que la acci\u00f3n de tutela \u201cs\u00f3lo proceder\u00e1 \u00a0 cuando el afectado no disponga de otro medio de defensa judicial, salvo que \u00a0 aqu\u00e9lla se utilice como mecanismo transitorio para evitar un perjuicio \u00a0 irremediable\u201d. A su vez, el art\u00edculo 6\u00ba del Decreto 2591 de 1991 indica que \u00a0 \u201cla existencia de dichos medios ser\u00e1 apreciada en concreto, en cuanto a su \u00a0 eficacia, atendiendo las circunstancias en que se encuentre el solicitante\u201d. \u00a0 \u00a0<\/p>\n<p>En el asunto bajo \u00a0 an\u00e1lisis, el Fondo Territorial de Pensiones de Santander emiti\u00f3 un acto \u00a0 administrativo que denomin\u00f3 \u201ccarta\u201d, en el cual indic\u00f3 a la accionante que su \u00a0 solicitud estaba incompleta porque deb\u00eda aportar un dictamen con una antig\u00fcedad \u00a0 menor a tres a\u00f1os[50]. \u00a0 La Sala destaca que, si bien tal documento tiene la naturaleza de acto \u00a0 administrativo, \u00e9ste no podr\u00eda ser controvertido judicialmente en tanto no \u00a0 involucra un pronunciamiento de fondo sobre el reconocimiento de la pensi\u00f3n. \u00a0 \u00a0<\/p>\n<p>Por lo tanto, la \u00a0 actora solo ten\u00eda a su disposici\u00f3n la acci\u00f3n de tutela para obtener la \u00a0 protecci\u00f3n de sus derechos fundamentales, lo que la torna procedente en el \u00a0 presente asunto. En consecuencia, se acreditan todos los presupuestos formales \u00a0 para proferir un fallo de fondo en el caso concreto. \u00a0 \u00a0<\/p>\n<p>3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Planteamiento del caso concreto, problemas jur\u00eddicos a resolver y metodolog\u00eda de \u00a0 resoluci\u00f3n \u00a0 \u00a0<\/p>\n<p>3.1.\u00a0\u00a0\u00a0 Aclaraci\u00f3n previa y planteamiento del caso \u00a0 \u00a0<\/p>\n<p>En \u00a0 primer lugar, la Sala Novena de Revisi\u00f3n destaca que a\u00fan no se ha dado tr\u00e1mite \u00a0 al recurso de reposici\u00f3n y en subsidio apelaci\u00f3n que la accionante formul\u00f3 \u00a0 contra el dictamen practicado por Medim\u00e1s EPS del 27 de septiembre de 2018. \u00a0 \u00a0<\/p>\n<p>El \u00a0 se\u00f1or Guillermo Calder\u00f3n inform\u00f3 en sede de revisi\u00f3n que present\u00f3 una acci\u00f3n de \u00a0 tutela diferente para amparar el derecho fundamental de petici\u00f3n de su hermana \u00a0 y, a pesar de que la autoridad judicial competente resolvi\u00f3 conceder el amparo, \u00a0 a la fecha no se ha dado cumplimiento a la orden del juez. \u00a0 \u00a0<\/p>\n<p>Frente al presente caso, se resalta que dicha acci\u00f3n pretende que se d\u00e9 tr\u00e1mite \u00a0 al recurso presentado por la actora y no el reconocimiento pensional pretendido \u00a0 en la tutela objeto de revisi\u00f3n bajo el amparo de los derechos fundamentales a \u00a0 la seguridad social y al m\u00ednimo vital, entre otros, por lo que se trata de \u00a0 asuntos diferentes. \u00a0 \u00a0<\/p>\n<p>Aunque la respuesta al referido recurso podr\u00eda eventualmente redundar en una \u00a0 modificaci\u00f3n de la fecha de estructuraci\u00f3n de invalidez y, a su vez, esto en el \u00a0 reconocimiento de la pensi\u00f3n solicitada, se trata de un escenario tan solo \u00a0 eventual, lo que exige a esta Corporaci\u00f3n pronunciarse de fondo sobre las \u00a0 pretensiones de la acci\u00f3n de tutela que fue seleccionada para revisi\u00f3n, en la \u00a0 cual se solicita ordenar al Fondo Territorial de Pensiones de Santander \u00a0 reconocer y pagar la pensi\u00f3n de sobrevivientes requerida por la se\u00f1ora Blanca \u00a0 Patricia Goyeneche. \u00a0 \u00a0<\/p>\n<p>La \u00a0 Corte evidencia que en el presente caso existen dos hechos claves que impidieron \u00a0 el acceso a la referida pensi\u00f3n: (i) el fondo pensional neg\u00f3 la solicitud de la \u00a0 accionante aduciendo que le faltaba un dictamen \u201cactualizado\u201d de su invalidez; \u00a0 y, (ii) Medim\u00e1s EPS determin\u00f3 como fecha de estructuraci\u00f3n de su discapacidad el \u00a0 mismo d\u00eda en que realiz\u00f3 la calificaci\u00f3n, pese a existir historial cl\u00ednico de su \u00a0 diagn\u00f3stico desde 1989. \u00a0 \u00a0<\/p>\n<p>3.2.\u00a0\u00a0\u00a0 Problemas jur\u00eddicos y estructura de la decisi\u00f3n \u00a0 \u00a0<\/p>\n<p>La \u00a0 Sala abordar\u00e1 los siguientes interrogantes: (i) \u00bfSe vulneran los derechos \u00a0 fundamentales al debido proceso y a la seguridad social cuando un fondo de \u00a0 pensiones exige un dictamen de p\u00e9rdida de capacidad laboral actualizado para \u00a0 estudiar una solicitud pensional? y, (ii) \u00bfSe desconoce el derecho fundamental \u00a0 al debido proceso cuando una autoridad calificadora establece como fecha de \u00a0 estructuraci\u00f3n de una invalidez el mismo d\u00eda en que se practic\u00f3 el dictamen, \u00a0 existiendo historial cl\u00ednico anterior sobre el diagn\u00f3stico del paciente? \u00a0 \u00a0<\/p>\n<p>Para \u00a0 resolver los puntos anteriores, la Corte abordar\u00e1: (i) los requisitos de la \u00a0 pensi\u00f3n de sobrevivientes para hijos en condici\u00f3n de invalidez y la exigencia de \u00a0 un dictamen \u201cactualizado\u201d; (ii) el derecho fundamental al debido proceso en la \u00a0 expedici\u00f3n de dict\u00e1menes de p\u00e9rdida de capacidad laboral; y, (iii) finalmente la \u00a0 soluci\u00f3n del caso concreto. \u00a0 \u00a0<\/p>\n<p>4. Los requisitos de la pensi\u00f3n de sobrevivientes para hijos en condici\u00f3n de \u00a0 invalidez y la exigencia de un dictamen \u201cactualizado\u201d \u00a0 \u00a0<\/p>\n<p>El \u00a0 art\u00edculo 47 de la Ley 100 de 1993 se\u00f1ala que \u201cson beneficiarios de la pensi\u00f3n \u00a0 de sobrevivientes (\u2026) c) los hijos inv\u00e1lidos si depend\u00edan econ\u00f3micamente del \u00a0 causante, mientras subsistan las condiciones de invalidez\u201d, y la disposici\u00f3n \u00a0 38 de esta misma ley refiere que \u201cse considera inv\u00e1lida la persona que por \u00a0 cualquier causa de origen no profesional, no provocada intencionalmente, hubiere \u00a0 perdido el 50% o m\u00e1s de su capacidad laboral\u201d. \u00a0 \u00a0<\/p>\n<p>En este sentido, se \u00a0 ha reiterado que los fondos pensionales solo pueden exigir aquellos documentos \u00a0 que \u201csean id\u00f3neos y necesarios\u201d para acreditar los requisitos mencionados[51], \u00a0 de lo contrario se podr\u00eda vulnerar el derecho fundamental al debido proceso \u00a0 administrativo y otras garant\u00edas que puedan versen afectadas por la negativa de \u00a0 una solicitud pensional. \u00a0 \u00a0<\/p>\n<p>La sentencia T-370 \u00a0 de 2017 refiere: \u201cLa exigencia de documentos adicionales, cuando los mismos \u00a0 no tienen un soporte previsto en el ordenamiento jur\u00eddico, se convierten en un \u00a0 obst\u00e1culo de car\u00e1cter meramente formal que conduce a una vulneraci\u00f3n del derecho \u00a0 fundamental al debido proceso administrativo, al tiempo que acarrea una \u00a0 afectaci\u00f3n grave al m\u00ednimo vital y a la vida digna, pues \u2013como ya se dijo\u2013 la \u00a0 pensi\u00f3n de sobrevivientes responde a la finalidad de garantizar las condiciones \u00a0 m\u00ednimas de subsistencia de quienes depend\u00edan econ\u00f3micamente del causante para \u00a0 atender sus necesidades b\u00e1sicas\u201d. \u00a0 \u00a0<\/p>\n<p>El fallo T-777 de \u00a0 2015 se\u00f1ala que la imposici\u00f3n de presupuestos adicionales para reclamar un \u00a0 derecho pensional implica el desconocimiento del principio de legalidad. En este \u00a0 caso, la Corte explic\u00f3 lo siguiente: \u00a0 \u00a0<\/p>\n<p>\u201cLos fondos de pensiones no pueden exigirle a los \u00a0 beneficiarios que pretenden el reconocimiento pensional, el cumplimento de \u00a0 formalidades no previstas legalmente, primero, porque el derecho a la pensi\u00f3n \u00a0 nace cuando se re\u00fanen los requisitos dispuestos en el ordenamiento para \u00a0 considerar que una persona es beneficiaria, por lo que en un contexto de \u00a0 libertad probatoria, cualquier imposici\u00f3n adicional supone la creaci\u00f3n de nuevos \u00a0 requisitos. Y segundo, porque dicha actuaci\u00f3n puede derivar en situaciones \u00a0 desproporcionadas a la luz de la Constituci\u00f3n, en cuanto la negativa impone \u00a0 cargas excesivas a personas que dadas sus circunstancias de debilidad \u00a0 manifiesta, son sujetos de especial protecci\u00f3n constitucional.\u201d \u00a0 \u00a0<\/p>\n<p>Por otra parte, se \u00a0 destaca que el art\u00edculo 44 de la Ley 100 de 1993 establece que, una vez otorgada \u00a0 la pensi\u00f3n de invalidez, las entidades correspondientes pueden revisar el estado \u00a0 de salud del beneficiario cada tres a\u00f1os para ratificar, modificar o dejar sin \u00a0 efectos el reconocimiento pensional: \u00a0 \u00a0<\/p>\n<p>\u201cART\u00cdCULO 44. REVISI\u00d3N DE LAS PENSIONES DE INVALIDEZ.\u00a0 \u00a0 El estado de invalidez podr\u00e1 revisarse: \u00a0 \u00a0<\/p>\n<p>a. Por solicitud de la entidad de previsi\u00f3n o seguridad \u00a0 social correspondiente cada tres (3) a\u00f1os, con el fin de ratificar, modificar o \u00a0 dejar sin efectos el dictamen que sirvi\u00f3 de base para la liquidaci\u00f3n de la \u00a0 pensi\u00f3n que disfruta su beneficiario y proceder a la extinci\u00f3n, disminuci\u00f3n o \u00a0 aumento de la misma, si a ello hubiera lugar. (\u2026)\u201d \u00a0 \u00a0<\/p>\n<p>Sobre la \u00a0 interpretaci\u00f3n de este art\u00edculo y la exigencia de un dictamen \u201cactualizado\u201d para \u00a0 acceder a una pensi\u00f3n, resulta especialmente importante la sentencia T-334 de \u00a0 2019 en la cual se resolvi\u00f3 la acci\u00f3n de tutela formulada por la se\u00f1ora Brenda \u00a0 Beatriz Eugenia Guzm\u00e1n Rueda contra el Fondo de Prestaciones Econ\u00f3micas, \u00a0 Cesant\u00edas y Pensiones &#8211; FONCEP, debido a que neg\u00f3 su solicitud de pensi\u00f3n de \u00a0 sobrevivientes como hija en condici\u00f3n de invalidez, aduciendo que deb\u00eda aportar \u00a0 un dictamen con menos de tres a\u00f1os de antig\u00fcedad. \u00a0 \u00a0<\/p>\n<p>En ese caso, se \u00a0 relata que la accionante ten\u00eda 75 a\u00f1os, hab\u00eda sido diagnosticada con \u00a0 esquizofrenia paranoide y su p\u00e9rdida de capacidad laboral fue determinada en \u00a0 un 62% por un dictamen practicado en el a\u00f1o 2012, debido a ello la entidad le \u00a0 exigi\u00f3 presentar una calificaci\u00f3n \u201cactualizada\u201d de su estado de invalidez. \u00a0 Respecto a tal exigencia, la Corte sostuvo:\u00a0 \u00a0 \u00a0<\/p>\n<p>\u201cesta Sala estima que las entidades encargadas de \u00a0 reconocer y pagar una sustituci\u00f3n pensional no pueden exigirle al posible \u00a0 beneficiario, que padezca de una enfermedad cr\u00f3nica, progresiva e incurable, \u00a0 que para efectos de acceder a dicha prestaci\u00f3n econ\u00f3mica tenga que allegar \u00a0 un dictamen &#8220;actualizado&#8221;, es decir, que haya sido realizado dentro de los \u00a0 tres a\u00f1os anteriores a la fecha en que se realiza la solicitud (interpretaci\u00f3n \u00a0 sostenida por la entidad accionada, la cual contiene un requisito que ha venido \u00a0 siendo exigido por parte de la misma, que involucra una carga innecesaria); pues \u00a0 aquella exigencia no ha sido prevista en la ley ni mucho menos en la \u00a0 jurisprudencia de la Corte Constitucional. \u00a0 \u00a0<\/p>\n<p>En efecto, el art\u00edculo 44 de la Ley 100 de 1993 \u00a0 \u00fanicamente permite la revisi\u00f3n del dictamen con posterioridad al reconocimiento \u00a0 de la pensi\u00f3n, caso en el cual la entidad correspondiente, en este caso el \u00a0 FONCEP, podr\u00eda solicitar una nueva valoraci\u00f3n cada tres a\u00f1os para verificar el \u00a0 estado de salud de la beneficiaria.[52]\u201d \u00a0 \u00a0<\/p>\n<p>La Corte enfatiz\u00f3 \u00a0 que la entidad pensional debi\u00f3 reconocer la prestaci\u00f3n social requerida en tanto \u00a0 cumpl\u00eda los requisitos previstos para ello y, si ten\u00eda alguna duda sobre el \u00a0 estado de salud actual de la peticionaria, deb\u00eda solicitar un nuevo dictamen a \u00a0 su costa, de conformidad con el art\u00edculo 44 de la Ley 100 de 1993. \u00a0 \u00a0<\/p>\n<p>As\u00ed las cosas, se \u00a0 enfatiza que los fondos pensionales s\u00f3lo pueden solicitar aquellos documentos \u00a0 que sean necesarios e id\u00f3neos para acreditar los requisitos legales propios de \u00a0 cada prestaci\u00f3n social. En el caso de la pensi\u00f3n de sobrevivientes para hijos en \u00a0 condici\u00f3n de discapacidad estos son: \u201c(i) la relaci\u00f3n filial; (ii) la \u00a0 situaci\u00f3n de discapacidad y que la misma hubiese generado perdida de la \u00a0 capacidad laboral igual o superior al 50%; y (iii) la dependencia econ\u00f3mica del \u00a0 hijo en situaci\u00f3n de discapacidad con el causante de la prestaci\u00f3n\u201d[53]; por lo que \u00a0 no puede exigirse un dictamen de p\u00e9rdida de capacidad laboral actualizado o con \u00a0 cierto rango de antig\u00fcedad como condici\u00f3n para estudiar una solicitud pensional. \u00a0 \u00a0<\/p>\n<p>5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 El derecho fundamental al debido proceso en la expedici\u00f3n de dict\u00e1menes de \u00a0 p\u00e9rdida de capacidad laboral. Reiteraci\u00f3n de jurisprudencia[54] \u00a0 \u00a0<\/p>\n<p>El proceso de \u00a0 expedici\u00f3n de dict\u00e1menes de p\u00e9rdida de capacidad laboral se rige por los \u00a0 art\u00edculos 38 a 43 de la Ley 100 de 1993 y los Decretos 917 de 1999, 2463 de 2001 \u00a0 y 1507 de 2014, este \u00faltimo establece el Manual \u00danico para la Calificaci\u00f3n de la \u00a0 P\u00e9rdida de la Capacidad Laboral y Ocupacional \u00a0 \u00a0<\/p>\n<p>Esta Corporaci\u00f3n ha \u00a0 establecido que el incumplimiento de estas reglas acarrea la vulneraci\u00f3n del \u00a0 derecho fundamental al debido proceso de los solicitantes y que el contenido \u00a0 m\u00ednimo de esta garant\u00eda se concreta en las siguientes cuatro reglas que deben \u00a0 ser cumplidas por todas las autoridades que realizan esta clase de ex\u00e1menes[55]: \u00a0 \u00a0<\/p>\n<p>(i)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0El dictamen debe \u00a0 realizarse cuando las entidades correspondientes hayan comprobado la \u00a0 imposibilidad de rehabilitaci\u00f3n del paciente[56]. \u00a0 \u00a0<\/p>\n<p>(ii)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0La valoraci\u00f3n que se \u00a0 realice debe ser completa e integral, de manera que se tengan en cuenta \u00a0todos los aspectos m\u00e9dicos consignados en el historial m\u00e9dico del \u00a0 solicitante[57]. \u00a0 \u00a0<\/p>\n<p>(iii)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0La decisi\u00f3n adoptada \u00a0 tiene que ser debidamente motivada y justificar las razones f\u00e1cticas y jur\u00eddicas \u00a0 que soportan el dictamen, siempre con base en la historia cl\u00ednica y ocupacional \u00a0 del paciente[58]. \u00a0 \u00a0<\/p>\n<p>(iv)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0La entidad \u00a0 correspondiente debe garantizar los derechos de defensa y contradicci\u00f3n de los \u00a0 solicitantes[59]. \u00a0 \u00a0<\/p>\n<p>Se resalta que en \u00a0 esta sentencia y en la T-595 de 2006, esta Corporaci\u00f3n abord\u00f3 casos en los \u00a0 cuales exist\u00edan errores en las fechas de estructuraci\u00f3n de los dict\u00e1menes \u00a0 realizados a los accionantes, en cuanto desconocieron aspectos relevantes de su \u00a0 historial m\u00e9dico. Lo que trajo como consecuencia que se ordenar\u00e1 la correcci\u00f3n \u00a0 respectiva. \u00a0 \u00a0<\/p>\n<p>La providencia \u00a0 T-012 de 2017 resolvi\u00f3 un caso en el que se negaba el reconocimiento de una \u00a0 pensi\u00f3n de sobrevivientes por diversas dificultades y errores a lo largo del \u00a0 tr\u00e1mite, uno de ellos era que el Instituto de Seguro Social hab\u00eda establecido \u00a0 que la fecha de estructuraci\u00f3n de la discapacidad de la accionante era el mismo \u00a0 d\u00eda en el que realiz\u00f3 el dictamen, lo cual resultaba equivocado de acuerdo a su \u00a0 historial cl\u00ednico. \u00a0 \u00a0<\/p>\n<p>La Corte reproch\u00f3 \u00a0 categ\u00f3ricamente tal decisi\u00f3n en los siguientes t\u00e9rminos: \u00a0 \u00a0<\/p>\n<p>\u201ces a todas luces contraevidente que se d\u00e9 por cierto \u00a0 que las enfermedades que aquejan a la actora se estructuraron en el mismo \u00a0 momento en que se llev\u00f3 a cabo la calificaci\u00f3n de la invalidez (\u2026). \u00a0 \u00a0<\/p>\n<p>Aceptar un exabrupto semejante equivaldr\u00eda a entender \u00a0 que la se\u00f1ora Elva Linares Camacho ingres\u00f3 en buen estado de salud a la \u00a0 valoraci\u00f3n con el m\u00e9dico ocupacional del Seguro Social y adquiri\u00f3 las patolog\u00edas \u00a0 de \u201cepilepsia parcial sintom\u00e1tica\u201d y \u201cretardo mental\u201d en el transcurso de la \u00a0 consulta con el galeno. \u00a0 \u00a0<\/p>\n<p>N\u00f3tese que el palmario el yerro que plasm\u00f3 el m\u00e9dico \u00a0 Santiago Buend\u00eda V\u00e1squez en dicho documento al indicar como fecha de \u00a0 estructuraci\u00f3n de la invalidez el mismo d\u00eda en que se emiti\u00f3 el oficio de la \u00a0 calificaci\u00f3n, sirvi\u00f3 de pretexto para que la entidad asumiera que la se\u00f1ora Elva \u00a0 Linares perdi\u00f3 su capacidad laboral con posterioridad al fallecimiento de su \u00a0 padre, cuando en realidad padec\u00eda dichas dolencias desde muy temprana edad.\u201d \u00a0 \u00a0<\/p>\n<p>En conclusi\u00f3n, la \u00a0 Corte enfatiza que las autoridades encargadas de realizar los ex\u00e1menes de \u00a0 p\u00e9rdida de capacidad laboral deben ce\u00f1irse a la normatividad aplicable y adoptar \u00a0 sus decisiones con base en una valoraci\u00f3n completa e integral de los \u00a0 antecedentes m\u00e9dicos del solicitante, lo cual reviste una especial importancia \u00a0 de cara a la fecha real en la que se estructura la discapacidad.\u00a0 \u00a0 \u00a0<\/p>\n<p>6.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Soluci\u00f3n del caso concreto \u00a0 \u00a0<\/p>\n<p>En el presente caso \u00a0 se evidencia que la se\u00f1ora Blanca Patricia Goyeneche Calder\u00f3n tiene 62 a\u00f1os de \u00a0 edad, fue diagnosticada con trastorno psic\u00f3tico y epilepsia desde 1989 y \u00a0 su p\u00e9rdida de capacidad laboral fue inicialmente determinada por la Junta \u00a0 Regional de Calificaci\u00f3n de Invalidez de Santander, quien en dictamen del 30 de \u00a0 abril de 2003 determin\u00f3 que ten\u00eda un porcentaje del 70% con fecha de \u00a0 estructuraci\u00f3n del 4 de septiembre de 2001. \u00a0 \u00a0<\/p>\n<p>As\u00ed mismo, se evidencia que la accionante depend\u00eda \u00a0 econ\u00f3micamente de su madre, la se\u00f1ora Elvia Calder\u00f3n de Goyeneche, debido a su \u00a0 estado de invalidez[62]. \u00a0 La se\u00f1ora Calder\u00f3n recib\u00eda una pensi\u00f3n de jubilaci\u00f3n a cargo del Fondo \u00a0 Territorial de Pensiones de la Gobernaci\u00f3n de Santander, sin embargo, la madre \u00a0 de la accionante falleci\u00f3 el 20 de mayo de 2018. \u00a0 \u00a0<\/p>\n<p>Esto trajo como \u00a0 consecuencia que la se\u00f1ora Blanca Patricia Goyeneche Calder\u00f3n quedar\u00e1 sin \u00a0 recursos para garantizar su propia subsistencia. Ante lo cual, solicit\u00f3 la \u00a0 pensi\u00f3n de sobreviviente como hija en condici\u00f3n de invalidez, para ello aport\u00f3 \u00a0 el dictamen de p\u00e9rdida de capacidad laboral que se le realiz\u00f3 el 30 de abril de \u00a0 2003, as\u00ed como su historial cl\u00ednico. \u00a0 \u00a0<\/p>\n<p>Pese a \u00a0 lo anterior, el Fondo Territorial de Pensiones de la Gobernaci\u00f3n de Santander \u00a0 neg\u00f3 el estudio de su solicitud se\u00f1alando que deb\u00eda aportar un dictamen \u00a0 \u201cactualizado\u201d que no tuviera una antig\u00fcedad mayor a tres a\u00f1os. Por lo tanto, \u00a0 acudi\u00f3 a la entidad a la cual estaba afiliada, Medim\u00e1s EPS, para solicitar una \u00a0 nueva calificaci\u00f3n. \u00a0 \u00a0\u00a0<\/p>\n<p>El \u00a0 27 de septiembre de 2018 esta entidad emiti\u00f3 dictamen de p\u00e9rdida de capacidad \u00a0 laboral en el que estableci\u00f3 un porcentaje del 70% y fecha de estructuraci\u00f3n el \u00a0 26 de septiembre de 2018. Frente a esta decisi\u00f3n, la accionante formul\u00f3 recurso \u00a0 de reposici\u00f3n y apelaci\u00f3n indicando que la fecha determinada no se correspond\u00eda \u00a0 con su historial cl\u00ednico en cuanto sus afecciones fueron diagnosticadas con a\u00f1os \u00a0 de anterioridad. No obstante, Medim\u00e1s EPS a\u00fan no ha dado tr\u00e1mite al referido \u00a0 recurso. \u00a0 \u00a0<\/p>\n<p>En \u00a0 consecuencia, el hermano de la actora, en calidad de agente oficioso, acudi\u00f3 a \u00a0 la acci\u00f3n de tutela solicitando el amparo de los derechos fundamentales de la \u00a0 se\u00f1ora Blanca Patricia a la vida, a la integridad, a la salud, a la seguridad \u00a0 social, al m\u00ednimo vital y de petici\u00f3n, as\u00ed como el tr\u00e1mite del recurso \u00a0 mencionado y el reconocimiento de la pensi\u00f3n de sobrevivientes en calidad de \u00a0 hija en condici\u00f3n de invalidez. \u00a0 \u00a0<\/p>\n<p>As\u00ed las \u00a0 cosas, la Sala Novena de Revisi\u00f3n se pronunciar\u00e1 en primer lugar sobre la \u00a0 negativa de la solicitud pensional de la accionante, en la que el fondo \u00a0 respectico argument\u00f3 que deb\u00eda aportar un dictamen \u201cactualizado\u201d de su p\u00e9rdida \u00a0 de capacidad laboral. \u00a0 \u00a0\u00a0<\/p>\n<p>Al respecto, se precisa que, tal como fue \u00a0 abordado en las consideraciones generales de esta providencia, los fondos \u00a0 pensionales deben examinar si el solicitante cumple con los requisitos legales \u00a0 para el reconocimiento de la pensi\u00f3n de sobreviviente para hijos en condici\u00f3n de \u00a0 invalidez, a saber, \u201c(i) la relaci\u00f3n filial; (ii) la situaci\u00f3n de \u00a0 discapacidad y que la misma hubiese generado perdida de la capacidad laboral \u00a0 igual o superior al 50%; y (iii) la dependencia econ\u00f3mica del hijo en situaci\u00f3n \u00a0 de discapacidad con el causante de la prestaci\u00f3n\u201d[63]. \u00a0 \u00a0<\/p>\n<p>Si un determinado \u00a0 fondo niega una solicitud con base en presupuestos adicionales a los descritos \u00a0 se vulnera el derecho fundamental al debido proceso y el principio \u00a0 constitucional de legalidad, as\u00ed como las garant\u00edas que puedan verse \u00a0 involucradas ante tal decisi\u00f3n. Frente al requerimiento de un dictamen \u00a0 \u201cactualizado\u201d para acceder al reconocimiento pensional, la Corte reitera que \u00a0 esta exigencia \u201cno ha sido prevista en la ley ni mucho menos en la \u00a0 jurisprudencia de la Corte Constitucional\u201d[64]. \u00a0 \u00a0<\/p>\n<p>Adem\u00e1s, el art\u00edculo \u00a0 44 de la Ley 100 de 1993 contempla la posibilidad de revisar el estado de \u00a0 invalidez de una persona cada tres a\u00f1os, pero con posterioridad a que se haya \u00a0 concedido la pensi\u00f3n. Por tanto, no puede exigirse dicha revisi\u00f3n como un \u00a0 requisito para estudiar de fondo una solicitud pensional o para reconocer la \u00a0 prestaci\u00f3n correspondiente. \u00a0 \u00a0<\/p>\n<p>La Corte encuentra \u00a0 que el Fondo Territorial de Pensiones de la Gobernaci\u00f3n de Santander exigi\u00f3 a la \u00a0 accionante un requisito no contemplado en la ley desconociendo as\u00ed su derecho \u00a0 fundamental al debido proceso y amenazando su garant\u00eda a la seguridad social. \u00a0 \u00a0<\/p>\n<p>Como segundo \u00a0 aspecto a abordar, la Sala pasa a estudiar el dictamen proferido por Medim\u00e1s \u00a0 EPS, en el que se estableci\u00f3 que la p\u00e9rdida de capacidad laboral de la se\u00f1ora \u00a0 Blanca Patricia se estructur\u00f3 el d\u00eda en que se llev\u00f3 a cabo la referida \u00a0 calificaci\u00f3n[65]. \u00a0 \u00a0<\/p>\n<p>La valoraci\u00f3n que \u00a0 realizan las entidades calificadoras debe ser completa e integral, \u00a0 lo que implica tener en cuenta todos aspectos que incluye la historia cl\u00ednica \u00a0 del solicitante. Este deber resulta especialmente importante a la hora de \u00a0 establecer la fecha de estructuraci\u00f3n, pues \u00e9sta indica el d\u00eda exacto en el que \u00a0 se configur\u00f3 la p\u00e9rdida de capacidad laboral registrada en el dictamen. \u00a0 \u00a0<\/p>\n<p>Tal como se sostuvo \u00a0 previamente, asegurar que una discapacidad o invalidez se estructur\u00f3 el mismo \u00a0 d\u00eda de la calificaci\u00f3n, implicar\u00eda que la persona ingres\u00f3 a valoraci\u00f3n en buen \u00a0 estado de salud y el mismo d\u00eda adquiri\u00f3 las patolog\u00edas correspondientes, lo cual \u00a0 desconocer\u00eda la situaci\u00f3n real del paciente, especialmente, en aquellos casos en \u00a0 los que las personas ya cuentan con antecedentes m\u00e9dicos de su enfermedad. \u00a0 \u00a0<\/p>\n<p>En el caso de la \u00a0 se\u00f1ora Blanca Patricia su condici\u00f3n de salud existe desde hace varios a\u00f1os y sus \u00a0 afecciones fueron diagnosticadas desde 1989[66], \u00a0 adicionalmente, el dictamen que se le practic\u00f3 en el a\u00f1o 2003 determin\u00f3 como \u00a0 fecha de estructuraci\u00f3n el 4 de septiembre de 2001[67]. \u00a0 \u00a0<\/p>\n<p>Por lo que afirmar \u00a0 que su invalidez se estructur\u00f3 el 26 de septiembre de 2018 se aleja de sus \u00a0 condiciones m\u00e9dicas, m\u00e1s a\u00fan, resulta reprochable que el mismo dictamen de \u00a0 Medim\u00e1s EPS refiere fechas de atenciones m\u00e9dicas y valoraciones anteriores (a\u00f1os \u00a0 2009-2015), y omite cualquier argumentaci\u00f3n que justifique por qu\u00e9 determin\u00f3 la \u00a0 fecha de estructuraci\u00f3n antedicha[68]. \u00a0 \u00a0<\/p>\n<p>Con lo cual, \u00a0 resulta claro que Medim\u00e1s EPS no realiz\u00f3 una valoraci\u00f3n completa e integral del \u00a0 historial m\u00e9dico de la accionante, lo que produjo un error a la hora de \u00a0 establecer la fecha en que se configur\u00f3 su p\u00e9rdida de capacidad laboral y, por \u00a0 ende, esto redund\u00f3 en un desconocimiento de su derecho fundamental al debido \u00a0 proceso. Lo cual se agrava a\u00fan m\u00e1s ante la renuencia de la entidad para dar \u00a0 tr\u00e1mite a los recursos interpuestos para rebatir esta fecha. \u00a0 \u00a0<\/p>\n<p>La Corte destaca \u00a0 que la se\u00f1ora Blanca Patricia Goyeneche Calder\u00f3n se vio enfrentada a diversos \u00a0 obst\u00e1culos que han impedido que se estudie su solicitud de pensi\u00f3n a pesar de \u00a0 acreditar los requisitos para su reconocimiento, tal como se explica a \u00a0 continuaci\u00f3n: \u00a0 \u00a0<\/p>\n<p>(i)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Relaci\u00f3n filial: la accionante acredit\u00f3 plenamente que era \u00a0 hija de la se\u00f1ora Elvia Calder\u00f3n de Goyeneche, quien recib\u00eda una pensi\u00f3n de \u00a0 jubilaci\u00f3n a cargo del Fondo Territorial de Pensiones de la Gobernaci\u00f3n de \u00a0 Santander[69]. \u00a0 \u00a0<\/p>\n<p>(ii)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0La situaci\u00f3n de \u00a0 discapacidad y que la misma hubiese generado perdida de la capacidad laboral \u00a0 igual o superior al 50%: la \u00a0 tutelante aport\u00f3 dos dict\u00e1menes que confirman su estado de invalidez. El primero \u00a0 se practic\u00f3 el d\u00eda 8 de octubre de 2001 por parte de CAPRECOM y se estableci\u00f3 un \u00a0 porcentaje de 52.9%[70], y el segundo tuvo lugar el 30 de abril \u00a0 de 2003, en el que la Junta Regional de Calificaci\u00f3n de Invalidez de Santander \u00a0 determin\u00f3 un porcentaje del 70% con fecha de estructuraci\u00f3n del 4 de septiembre \u00a0 de 2001[71]. \u00a0 \u00a0<\/p>\n<p>(iii)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0La dependencia \u00a0 econ\u00f3mica del hijo en situaci\u00f3n de discapacidad con el causante de la \u00a0 prestaci\u00f3n. La cual se \u00a0 acredit\u00f3 con el Acuerdo No. II de la Junta Directiva del Instituto del Seguro \u00a0 Social de Santander aprobado el 26 de julio de 1991, mediante el cual se \u00a0 autoriza atenci\u00f3n m\u00e9dica a la se\u00f1ora Blanca Patricia Goyeneche Calder\u00f3n en \u00a0 condici\u00f3n de hija con discapacidad[72], \u00a0 y los dos dict\u00e1menes ya referidos que se practicaron en los a\u00f1os 2001 y 2003, \u00a0 que tambi\u00e9n indican la falta de antecedentes laborales o ingresos propios de la \u00a0 actora[73]. \u00a0 \u00a0<\/p>\n<p>As\u00ed las cosas, la Sala conceder\u00e1 el amparo a los \u00a0 derechos fundamentales al debido proceso y a la seguridad social de la \u00a0 accionante, y ordenar\u00e1 al Fondo Territorial de Pensiones de la Gobernaci\u00f3n de \u00a0 Santander que estudie la solicitud de reconocimiento pensional de la actora, con \u00a0 fundamento en el dictamen de p\u00e9rdida de capacidad laboral emitido el 30 de abril \u00a0 de 2003 por la Junta Regional de Calificaci\u00f3n de Invalidez de Santander, y \u00a0 conforme a los lineamientos expuestos en esta sentencia. \u00a0 \u00a0<\/p>\n<p>7. S\u00edntesis de la decisi\u00f3n \u00a0 \u00a0<\/p>\n<p>La Sala Novena de Revisi\u00f3n aborda el caso de \u00a0 Blanca Patricia Goyeneche Calder\u00f3n, quien cuenta con 62 a\u00f1os de edad y fue \u00a0 diagnosticada con trastorno psic\u00f3tico cr\u00f3nico y epilepsia desde 1989, por \u00a0 lo que dependi\u00f3 de su progenitora hasta la fecha de su fallecimiento en mayo de \u00a0 2018. Ante tal escenario, solicit\u00f3 pensi\u00f3n de sobrevivientes como hija en \u00a0 condici\u00f3n de invalidez y aport\u00f3 dos dict\u00e1menes de p\u00e9rdida de capacidad laboral \u00a0 de los a\u00f1os 2001 y 2003, en los cuales se acreditan porcentajes de invalidez del \u00a0 52.9% y 70%, respectivamente. \u00a0 \u00a0<\/p>\n<p>El Fondo Territorial de Pensiones de la \u00a0 Gobernaci\u00f3n de Santander se abstuvo de estudiar la petici\u00f3n asegurando que deb\u00eda \u00a0 aportar un dictamen que no tuviera m\u00e1s de tres a\u00f1os de antig\u00fcedad. En \u00a0 consecuencia, la se\u00f1ora Blanca Patricia Goyeneche acudi\u00f3 a Medim\u00e1s EPS para la \u00a0 realizaci\u00f3n de un nuevo dictamen, el cual se practic\u00f3 el d\u00eda 27 de septiembre de \u00a0 2018 y confirm\u00f3 el 70% de invalidez, sin embargo, estableci\u00f3 que la fecha de \u00a0 estructuraci\u00f3n de la discapacidad era el mismo d\u00eda de la calificaci\u00f3n, lo cual \u00a0 creaba un obst\u00e1culo adicional al tratarse de una fecha posterior al \u00a0 fallecimiento de la madre de la accionante. \u00a0 \u00a0<\/p>\n<p>Ante tal escenario, la actora present\u00f3 \u00a0 recurso de reposici\u00f3n y apelaci\u00f3n contra este dictamen con fundamento en que \u00a0 exist\u00eda un error en la fecha de estructuraci\u00f3n, no obstante, hasta el momento \u00a0 Medim\u00e1s EPS no le ha dado tr\u00e1mite alguno a dicho recurso. Como consecuencia de \u00a0 lo anterior, Guillermo Calder\u00f3n, en calidad de agente oficioso de su hermana, \u00a0 solicit\u00f3 el amparo de sus derechos fundamentales a la seguridad social, a la \u00a0 integridad, al m\u00ednimo vital, entre otros, as\u00ed como el reconocimiento de la \u00a0 pensi\u00f3n de sobrevivientes como hija en condici\u00f3n de invalidez. \u00a0 \u00a0<\/p>\n<p>Para resolver el caso, la Corte \u00a0 Constitucional aborda en primer lugar la procedencia formal de la acci\u00f3n de \u00a0 tutela, encontrando que cumple con los requisitos de legitimaci\u00f3n en la causa \u00a0 por activa y pasiva, inmediatez y subsidiariedad. Se resalta que la accionante \u00a0 es sujeto de especial protecci\u00f3n constitucional en tanto se encuentra en \u00a0 un grave estado de vulnerabilidad, debido a sus condiciones de salud y la falta \u00a0 de recursos para garantizar su propio sostenimiento. \u00a0 \u00a0<\/p>\n<p>Respecto al fondo del caso, se corrobora que \u00a0 existen dos hechos clave que llevaron a negar la solicitud pensional de la \u00a0 actora: (i) la exigencia de un dictamen \u201cactualizado\u201d; y, (ii) la determinaci\u00f3n \u00a0 de la fecha de estructuraci\u00f3n del dictamen de p\u00e9rdida de capacidad laboral \u00a0 practicado por Medim\u00e1s EPS. \u00a0 \u00a0<\/p>\n<p>En consecuencia, la Corte aborda el estudio \u00a0 de los siguientes problemas jur\u00eddicos: (i) \u00bfSe vulneran los derechos \u00a0 fundamentales al debido proceso y a la seguridad social cuando un fondo de \u00a0 pensiones exige un dictamen de p\u00e9rdida de capacidad laboral \u201cactualizado\u201d para \u00a0 estudiar una solicitud pensional? y, (ii) \u00bfSe desconoce el derecho fundamental \u00a0 al debido proceso cuando una autoridad calificadora establece como fecha de \u00a0 estructuraci\u00f3n de una invalidez el mismo d\u00eda en que se practic\u00f3 el dictamen, \u00a0 existiendo historial cl\u00ednico anterior sobre el diagn\u00f3stico del paciente? \u00a0 \u00a0<\/p>\n<p>A su vez, se destaca que la exigencia de un \u00a0 dictamen \u201cactualizado\u201d carece de fundamento legal o jurisprudencial, por lo que \u00a0 no puede ser un obst\u00e1culo para el reconocimiento de una pensi\u00f3n, m\u00e1s a\u00fan, se \u00a0 resalta que tal requerimiento redunda en una vulneraci\u00f3n del derecho fundamental \u00a0 al debido proceso y en una amenaza a la garant\u00eda de la seguridad social[75]. \u00a0 \u00a0<\/p>\n<p>Por otra parte, la Corte enfatiza que las \u00a0 autoridades que realizan dict\u00e1menes de p\u00e9rdida de capacidad laboral tienen la \u00a0 obligaci\u00f3n de valorar de manera completa e integral todos los \u00a0 aspectos relevantes de la historia cl\u00ednica del paciente, m\u00e1s a\u00fan, a la hora de \u00a0 establecer la fecha de estructuraci\u00f3n de la discapacidad. \u00a0 \u00a0<\/p>\n<p>Frente a esta \u00faltima, se reitera que \u00a0 vincular esa fecha al d\u00eda en que se realiz\u00f3 la calificaci\u00f3n, equivaldr\u00eda a \u00a0 sostener que el solicitante adquiri\u00f3 sus afecciones de salud en la misma fecha \u00a0 que se emiti\u00f3 el dictamen, lo cual resultar\u00eda ajeno a la realidad, \u00a0 especialmente, cuando existen antecedentes m\u00e9dicos que acreditan las afecciones \u00a0 del paciente[76]. \u00a0 \u00a0<\/p>\n<p>As\u00ed las cosas, la Sala Novena de Revisi\u00f3n \u00a0 encuentra que el Fondo Territorial de Pensiones de la Gobernaci\u00f3n de Santander y \u00a0 Medim\u00e1s EPS vulneraron la garant\u00eda del debido proceso y amenazaron el derecho \u00a0 fundamental a la seguridad social, por lo que se ordena al fondo mencionado, que \u00a0 estudie la solicitud pensional de la actora con fundamento en el dictamen \u00a0 realizado el 30 de abril de 2003 y conforme a los lineamientos de esta \u00a0 sentencia. \u00a0 \u00a0<\/p>\n<p>III. DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Novena de \u00a0 Revisi\u00f3n, administrando justicia en nombre del pueblo y por mandato de la \u00a0 Constituci\u00f3n Pol\u00edtica, \u00a0 \u00a0<\/p>\n<p>RESUELVE: \u00a0 \u00a0<\/p>\n<p>Primero.- REVOCAR la sentencias proferidas el 17 de enero de \u00a0 2019, por el Juzgado 68 Civil Municipal de Oralidad de Bogot\u00e1 D.C., en primera \u00a0 instancia, y el 26 de febrero de 2019, por el Juzgado 21 Civil del Circuito de \u00a0 esa misma ciudad, en segunda instancia, los cuales negaron la acci\u00f3n de tutela \u00a0 formulada por Guillermo Calder\u00f3n, en calidad de agente oficioso de Blanca \u00a0 Patricia Goyeneche Calder\u00f3n, contra Medim\u00e1s EPS, el Fondo Territorial de \u00a0 Pensiones de Santander y la Junta Regional de Calificaci\u00f3n de Invalidez de \u00a0 Santander. En su lugar, AMPARAR los derechos fundamentales al debido \u00a0 proceso y a la seguridad social de la se\u00f1ora Blanca Patricia Goyeneche Calder\u00f3n. \u00a0 \u00a0<\/p>\n<p>Segundo.- ORDENAR al Fondo Territorial de Pensiones de Santander que, \u00a0 dentro de los diez (10) d\u00edas siguientes a la notificaci\u00f3n de este fallo, estudie \u00a0 la solicitud de reconocimiento de la pensi\u00f3n de sobrevivientes en calidad de \u00a0 hija en condici\u00f3n de invalidez de la se\u00f1ora Blanca Patricia Goyeneche \u00a0 Calder\u00f3n, con base en el dictamen de p\u00e9rdida de capacidad laboral emitido por la \u00a0 Junta Regional de Calificaci\u00f3n de Invalidez de Santander el 30 de abril de 2003 \u00a0 y conforme a los lineamientos expuestos en esta sentencia. \u00a0 \u00a0<\/p>\n<p>Tercero.- L\u00cdBRESE por Secretar\u00eda General la comunicaci\u00f3n prevista en el \u00a0 art\u00edculo 36 del Decreto 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>ALBERTO ROJAS R\u00cdOS \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>CARLOS BERNAL PULIDO \u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0 \u00a0<\/p>\n<p>DIANA \u00a0 FAJARDO RIVERA \u00a0 \u00a0<\/p>\n<p>Magistrada \u00a0 \u00a0<\/p>\n<p>Con aclaraci\u00f3n de voto \u00a0 \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>ACLARACI\u00d3N DE VOTO DE LA MAGISTRADA \u00a0 \u00a0<\/p>\n<p>DIANA \u00a0 FAJARDO RIVERA \u00a0 \u00a0<\/p>\n<p>\u00a0A LA \u00a0 SENTENCIA T-524\/19 \u00a0 \u00a0<\/p>\n<p>DEBIDO PROCESO EN LA EXPEDICION DE LOS \u00a0 DICTAMENES DE PERDIDA DE LA CAPACIDAD LABORAL-Posibilidad \u00a0 de exigir dict\u00e1menes de incapacidad actualizados \u00a0 (Aclaraci\u00f3n de voto) \u00a0 \u00a0<\/p>\n<p>No \u00a0 comparto la subregla que trae el proyecto seg\u00fan la cual las entidades a cargo de \u00a0 reconocer el derecho pensional nunca podr\u00e1n requerir un certificado de p\u00e9rdida \u00a0 de capacidad actualizado, al momento de resolver la \u00a0 solicitud por primera vez. Una regla as\u00ed de absoluta (i) desconoce que la \u00a0 incapacidad no es una condici\u00f3n est\u00e1tica e inmodificable del ser humano; (ii) \u00a0 genera un riesgo de fraude para personas cuya incapacidad se haya superado, \u00a0 siquiera parcialmente; y (iii) parad\u00f3jicamente relega \u00a0 a las mismas personas que se busca proteger bajo un r\u00f3tulo indeleble de \u00a0 \u201cinvalidez\u201d. Lo anterior no significa que siempre sea razonable exigir una \u00a0 constancia actualizada, pues claramente ello no ser\u00e1 necesario si, por ejemplo, tan solo ha trascurrido un corto \u00a0 intervalo de tiempo. \u00a0 \u00a0<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Acompa\u00f1\u00e9 la Sentencia T-524 de 2019[77], que \u00a0 tutel\u00f3 los derechos fundamentales al debido proceso y a la seguridad social de \u00a0 la se\u00f1ora Blanca Patricia Goyeneche Calder\u00f3n. Comparto la decisi\u00f3n a la que \u00a0 lleg\u00f3 la Sala, en tanto que, la EPS Medim\u00e1s -de forma arbitraria- estableci\u00f3 \u00a0 como fecha de estructuraci\u00f3n el mismo d\u00eda en que se \u00a0 produjo el dictamen. Con ello, la entidad desconoci\u00f3 la condici\u00f3n de salud que \u00a0 aqueja a la se\u00f1ora Blanca de tiempo atr\u00e1s, y que fue diagnosticada por primera \u00a0 vez en 1989. Lo anterior era raz\u00f3n suficiente para conceder el amparo. Sin embargo, la Sentencia trae otro argumento \u00a0 relacionado con la imposibilidad de exigir un dictamen m\u00e9dico actualizado. Este \u00a0 segundo argumento es lo que me lleva a aclarar mi voto, pues considero que en \u00a0 algunas circunstancias podr\u00eda ser razonable requerir \u00a0 una valoraci\u00f3n actualizada. \u00a0 \u00a0<\/p>\n<p>2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La \u00a0 posici\u00f3n mayoritaria parece haber formulado una regla absoluta seg\u00fan la cual, \u00a0 bajo ninguna circunstancia, las entidades del sistema de seguridad social pueden \u00a0 solicitar un dictamen actualizado, pues tal requisito carece de fundamento legal o jurisprudencial[78]. \u00a0 Seg\u00fan esta postura, en caso de duda sobre el estado de salud de un peticionario, \u00a0 la entidad est\u00e1 obligada a esperar tres a\u00f1os, luego de reconocida la pensi\u00f3n, \u00a0 para reexaminar al solicitante; pero nunca podr\u00eda hacerlo al momento de conocer por primera vez la solicitud de \u00a0 pensi\u00f3n. \u00a0 \u00a0<\/p>\n<p>3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 Contrario a lo que sostuvieron mis compa\u00f1eros de Sala, creo que el asunto es m\u00e1s \u00a0 complejo de lo que parece inicialmente. No se puede descartar que en \u00a0 determinadas circunstancias resulte razonable, ante el \u00a0 paso del tiempo, solicitar un certificado de invalidez actualizado; claro est\u00e1, \u00a0 en el entendido de que dicha exigencia no se convierta en un obst\u00e1culo \u00a0 desproporcionado para el solicitante, ya sea por razones econ\u00f3micas, log\u00edsticas \u00a0 o de otro \u00edndole, que hagan nugatorio el tr\u00e1mite \u00a0 pensional. \u00a0 \u00a0<\/p>\n<p>4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Es \u00a0 cierto que no existe una norma espec\u00edfica que regule la vigencia que puede tener \u00a0 un certificado de invalidez, cuando se eleva una solicitud por primera vez. A lo \u00a0 que s\u00ed se refiere la Ley 100 de 1993, en su art\u00edculo \u00a0 44, es a la posibilidad de revisar peri\u00f3dicamente la condici\u00f3n de salud respecto \u00a0 a beneficiarios con pensiones ya reconocidas. Lo anterior sugiere la necesidad \u00a0 de revisar peri\u00f3dicamente la real condici\u00f3n de salud de una persona, de manera \u00a0 que se salvaguarden intereses constitucionales importantes, ante eventuales \u00a0 casos de fraude[79]. \u00a0 Adem\u00e1s, las enfermedades o accidentes incapacitantes tienen una naturaleza \u00a0 variable, de modo que el estado de salud puede extinguirse, mantenerse o \u00a0 agravarse en el tiempo[80]. \u00a0 Siguiendo esta argumentaci\u00f3n, recientemente la Sala Segunda de Revisi\u00f3n lleg\u00f3 a \u00a0 la conclusi\u00f3n que Colpensiones no hab\u00eda vulnerado los derechos fundamentales a \u00a0 la seguridad social y m\u00ednimo vital del accionante, al condicionar, \u00a0 razonablemente, el estudio de la solicitud de pensi\u00f3n de invalidez a una \u00a0 actualizaci\u00f3n de la p\u00e9rdida de capacidad laboral, puesto que trascurrieron doce \u00a0 a\u00f1os desde el primer examen y la solicitud pensional: \u00a0 \u00a0<\/p>\n<p>\u201cNo existen \u00a0 mandatos legales taxativos de vigencia de los \u00a0 dict\u00e1menes ni t\u00e9rminos de caducidad, y por tanto no es labor del juez \u00a0 constitucional crear presupuestos temporales fijos o introducir criterios \u00a0 r\u00edgidos sobre la materia. Con todo, debe recordarse que el trasfondo de la \u00a0 figura de la \u201crevisi\u00f3n \u00a0 del estado de invalidez\u201d \u00a0 persigue la realizaci\u00f3n de intereses constitucionales importantes, como lo son \u00a0 la equidad y la salvaguarda jur\u00eddica del sistema de pensiones, evitando, por \u00a0 ejemplo, casos de fraude. En ese sentido, observa la Sala que si el car\u00e1cter \u00a0 variable del riesgo hace exigible a las entidades \u00a0 pensionales la verificaci\u00f3n de la actualidad del mismo respecto de quienes ya se \u00a0 han hecho acreedores de la prestaci\u00f3n, no hay raz\u00f3n alguna para entender que \u00a0 ello sea distinto en el caso de aquellos que solicitan por primera vez la pensi\u00f3n de invalidez, m\u00e1s aun si \u00e9sta se \u00a0 encuentra basada en un dictamen que data de una fecha irrazonablemente lejana de \u00a0 aquella en la que se eleva la solicitud. \u00a0 \u00a0<\/p>\n<p>As\u00ed las cosas, es \u00a0 importante establecer que la protecci\u00f3n del riesgo de invalidez responde, justamente, a la necesidad de asegurar \u00a0 econ\u00f3micamente a aquellas personas que, cumpliendo los dem\u00e1s requisitos legales, \u00a0 y por sus condiciones m\u00e9dicas, les es imposible desarrollar su fuerza de trabajo \u00a0 ordinaria, por presentar una p\u00e9rdida funcional \u00a0 significativa. Siendo ello as\u00ed, es evidente que este tipo de prestaci\u00f3n exige \u00a0 una condici\u00f3n cl\u00ednica actual para ser titular de la misma, sobre todo en \u00a0 aquellos casos en los que la situaci\u00f3n de invalidez se ha derivado de una \u00a0 enfermedad degenerativa o progresiva. De ah\u00ed que, al \u00a0 estudiar por primera vez el reconocimiento de pensi\u00f3n de invalidez, la entidad \u00a0 pensional se encuentre autorizada para requerir una actualizaci\u00f3n del dictamen \u00a0 aportado, siempre y cuando, de acuerdo con las particularidades de cada caso, sea razonablemente evidente la necesidad de \u00a0 verificar la vigencia de la p\u00e9rdida de capacidad\u201d[81]. \u00a0 \u00a0<\/p>\n<p>5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 As\u00ed \u00a0 las cosas, no comparto la subregla que trae el proyecto seg\u00fan la cual las \u00a0 entidades a cargo de reconocer el derecho pensional nunca \u00a0podr\u00e1n requerir un certificado de p\u00e9rdida de capacidad actualizado, al momento \u00a0 de resolver la solicitud por primera vez. Una regla as\u00ed de absoluta (i) \u00a0 desconoce que la incapacidad no es una condici\u00f3n est\u00e1tica e inmodificable del \u00a0 ser humano; (ii) genera un riesgo de fraude para \u00a0 personas cuya incapacidad se haya superado, siquiera parcialmente; y (iii) \u00a0 parad\u00f3jicamente relega a las mismas personas que se busca proteger bajo un \u00a0 r\u00f3tulo indeleble de \u201cinvalidez\u201d. Lo \u00a0 anterior no significa que siempre sea razonable \u00a0exigir una constancia actualizada, pues \u00a0 claramente ello no ser\u00e1 necesario si, por ejemplo, tan solo ha trascurrido un \u00a0 corto intervalo de tiempo. \u00a0 \u00a0<\/p>\n<p>6.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En \u00a0 este caso concreto, no parec\u00eda irrazonable que el Fondo Territorial de Pensiones \u00a0 de Santander solicitara un certificado actualizado, \u00a0 dado que la solicitud de pensi\u00f3n de sobrevivientes se elev\u00f3 en 2018, aportando \u00a0 un dictamen de invalidez practicado en 2005. Aunque la se\u00f1ora Blanca Patricia ha \u00a0 sido diagnosticada con una enfermedad cr\u00f3nica y progresiva, era v\u00e1lido \u00a0 preguntarse por la evoluci\u00f3n o empeoramiento en su condici\u00f3n de salud, luego de \u00a0 quince a\u00f1os. Esta exigencia tampoco resultaba ser un obst\u00e1culo desproporcionado \u00a0 para la accionante y su grupo familiar, pues al poco tiempo se practic\u00f3 un nuevo \u00a0 dictamen m\u00e9dico. El problema central radic\u00f3, m\u00e1s bien, en la valoraci\u00f3n \u00a0 arbitraria que realiz\u00f3 el equipo m\u00e9dico sobre la fecha de estructuraci\u00f3n, en \u00a0 abierto desconocimiento de la historia cl\u00ednica de la paciente. \u00a0 \u00a0<\/p>\n<p>7.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En \u00a0 resumen, pienso que era posible salvaguardar el derecho \u00a0 fundamental a la seguridad social de la se\u00f1ora Blanca Patricia, sin necesidad de \u00a0 negar absolutamente la posibilidad de exigir dict\u00e1menes de incapacidad \u00a0 actualizados, desconociendo con ello las particularidades que pueden presentarse \u00a0 en cada caso concreto as\u00ed como los dem\u00e1s intereses \u00a0 constitucionales en tensi\u00f3n. \u00a0 \u00a0<\/p>\n<p>Fecha ut supra \u00a0 \u00a0<\/p>\n<p>DIANA FAJARDO RIVERA \u00a0 \u00a0<\/p>\n<p>Magistrada \u00a0 \u00a0<\/p>\n<p>[1] Espec\u00edficamente \u00a0 las previstas en los art\u00edculos 86 y 241 numeral 9\u00ba de la Constituci\u00f3n Pol\u00edtica, \u00a0 y en los art\u00edculos 33 y siguientes del Decreto 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>[2] Cuaderno de \u00a0 Revisi\u00f3n. Folio 8. La Sala de Selecci\u00f3n de Tutelas N\u00famero Cinco estuvo \u00a0 conformada por el Magistrado Antonio Jos\u00e9 Lizarazo Ocampo y la Magistrada Gloria \u00a0 Stella Ortiz Delgado. \u00a0 \u00a0<\/p>\n<p>[3] Ver Folio 28 del Cuaderno Principal. Textualmente la certificaci\u00f3n \u00a0 m\u00e9dica expedida por el galeno tratante indic\u00f3 al respecto: \u201cPor medio del \u00a0 presente certific\u00f3 que desde hace varios a\u00f1os vengo prestando mis servicios \u00a0 profesionales a la paciente Blanca Patricia Goyeneche quien presenta trastorno \u00a0 psic\u00f3tico cr\u00f3nico y epilepsia, ambas enfermedades altamente incapacitantes y de \u00a0 curso cr\u00f3nico que le impiden valerse por s\u00ed misma y requiere protecci\u00f3n \u00a0 permanente\u201d. \u00a0 \u00a0<\/p>\n<p>[4] Ver Folio 26 de Cuaderno \u00a0 Principal. Certificaci\u00f3n del M\u00e9dico Psiquiatra Armando Puyo Tibaquira, expedida \u00a0 el 29 de noviembre de 2018, la cual concuerda con la Certificaci\u00f3n del M\u00e9dico \u00a0 Psiquiatra Juan Carlos Mart\u00ednez Santoro del 02 de noviembre de 2004, en la cual \u00a0 se afirma que las enfermedades diagnosticadas a la accionante son \u201cprogresivas, \u00a0 incapacitantes y deteriorantes e incurables\u201d. Ver folio 52 del Cuaderno de \u00a0 Revisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>[5] Ver Folio 135 \u00a0 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[6] Ver Folios 32-37 \u00a0 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[7] En el \u00a0 expediente se incluye copia del Acuerdo No. II de la Junta Directiva del \u00a0 Instituto del Seguro Social de Santander aprobado el 26 de julio de 1991, \u00a0 mediante el cual autoriza atenci\u00f3n m\u00e9dica a la se\u00f1ora Blanca Patricia Goyeneche \u00a0 Calder\u00f3n en condici\u00f3n de hija con discapacidad. Ver folio 22 del Cuaderno \u00a0 Principal. Adem\u00e1s, en los dict\u00e1menes reci\u00e9n mencionados se se\u00f1ala que nunca ha \u00a0 trabajado y no se registra ning\u00fan antecedente laboral. \u00a0 \u00a0<\/p>\n<p>[8] Ver Folio 47 del \u00a0 Cuaderno Principal. A trav\u00e9s de Resoluci\u00f3n No. J-53 del 1 de febrero de 1982, el \u00a0 Instituto de Seguro Social de Santander reconoci\u00f3 pensi\u00f3n de jubilaci\u00f3n en favor \u00a0 de Elvia Calder\u00f3n de Goyeneche. \u00a0 \u00a0<\/p>\n<p>[9] Ver Folio 45 del \u00a0 Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[10] Ver Folios \u00a0 166-172 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[11] Ver Folios \u00a0 242-244 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[12] Ver Folios \u00a0 32-37 del Cuaderno Principal. La Corte advierte que la \u00a0 fecha del dictamen no fue el 26 sino el 27 de septiembre. Ver Folios 242-244 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[13] Ver Folios 18 \u00a0 al 28 del Cuaderno de Revisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>[14] Ver Folio 7 \u00a0 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[15] Ver Folio 187 \u00a0 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[16] Ver Folios \u00a0 237-239 del Cuaderno Principal. \u00c9nfasis agregado. \u00a0 \u00a0<\/p>\n<p>[17] Ver Folios \u00a0 280-281 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[18] Ver Folios 247-253 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[19] Ver Folios 255-262 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[20] Ver Folio 286 \u00a0 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[21] Ver Folios 290-296 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[22] Ver Folios 320-333 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[23] Ver Folios \u00a0 369-375 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[24] Ver Folios 3-5 del Cuaderno de Segunda Instancia. \u00a0 \u00a0<\/p>\n<p>[25] Ver Folios \u00a0 19-51 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[26] Ver Folios \u00a0 19-21 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[27] Ver Folio 46 \u00a0del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[28] Ver Folio 47 \u00a0del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[29] Ver Folio 28 \u00a0del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[30] Ver Folio 50 \u00a0del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[31] Ver Folio 22 \u00a0del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[32] Ver Folio 48 \u00a0del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[33] Ver Folios 51 \u00a0 y 52 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[34] Ver Folio 25 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[35] Ver Folio 45 \u00a0del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[36] Ver Folio \u00a0 32-37 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[37] Ver Folios 18 \u00a0 al 28 del Cuaderno de Revisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>[38] Ver Folio 26 \u00a0 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[39] Ver Folios 18 \u00a0 al 28 del Cuaderno de Revisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>[40] Ver Folios 65-66 del Cuaderno \u00a0 de Revisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>[41] Ver \u00a0 Folio 65 del Cuaderno de Revisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>[43] Sentencia \u00a0 SU-267 de 2019. \u00a0 \u00a0<\/p>\n<p>[44] Sentencia T-353 \u00a0 de 2018. \u00a0 \u00a0<\/p>\n<p>[45] Las Sentencias \u00a0 SU-055 de 2015 y T-430 de 2017 establecen en este sentido: \u201cPara que se \u00a0 configure la agencia oficiosa, la concurrencia de dos elementos: (i) que el \u00a0 titular de los derechos no est\u00e9 en condiciones de defenderlos y, (ii) que en la \u00a0 tutela se manifieste esa circunstancia. En cuanto a esta \u00faltima exigencia, su \u00a0 cumplimiento s\u00f3lo se puede verificar en presencia de personas en estado \u00a0 de vulnerabilidad extrema, en circunstancias de debilidad manifiesta o de \u00a0 especial sujeci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>[46] Ver sentencia \u00a0 SU-267 de 2019. En t\u00e9rminos generales, el art\u00edculo 86 de la Constituci\u00f3n indica \u00a0 que procede contra \u201cencargados de la prestaci\u00f3n de un servicio p\u00fablico o cuya \u00a0 conducta afecte grave y directamente el inter\u00e9s colectivo, o respecto de quienes \u00a0 el solicitante se halle en estado de subordinaci\u00f3n o indefensi\u00f3n.\u201d. \u00a0 \u00a0<\/p>\n<p>[47] Entidad del \u00a0 Sistema de la Seguridad Social Integral del orden nacional, de creaci\u00f3n legal, \u00a0 adscrita al Ministerio del Trabajo, con personer\u00eda jur\u00eddica, de derecho \u00a0 privado, sin \u00e1nimo de lucro, de car\u00e1cter interdisciplinario, sujeta a \u00a0 revisor\u00eda fiscal, con autonom\u00eda t\u00e9cnica y cient\u00edfica en los dict\u00e1menes \u00a0 periciales, cuyas decisiones son de car\u00e1cter obligatorio. \u00a0 \u00a0<\/p>\n<p>[48] El art\u00edculo 86 Superior dispone: (\u2026) La ley establecer\u00e1 los casos \u00a0 en los que la acci\u00f3n de tutela procede contra particulares encargados de la \u00a0 prestaci\u00f3n de un servicio p\u00fablico o cuya conducta afecte grave y directamente el \u00a0 inter\u00e9s colectivo, o respecto de quienes el solicitante se halle en estado de \u00a0 subordinaci\u00f3n o indefensi\u00f3n.\u201d. El texto normativo que regul\u00f3 estos aspectos \u00a0 fue el Decreto 2591 de 1991, cuyo art\u00edculo 42 establece: \u201cLa acci\u00f3n de tutela \u00a0 proceder\u00e1 contra acciones u omisiones de particulares en los siguientes casos: \u00a0 (\u2026) 3. Cuando aqu\u00e9l contra quien se hubiere hecho la solicitud est\u00e9 encargado \u00a0 de la prestaci\u00f3n de servicios p\u00fablicos\u201d \u00c9nfasis agregado. \u00a0 \u00a0<\/p>\n<p>[49] Sentencias \u00a0 C-543 de 1992, T-353 de 2018, entre otras. \u00a0 \u00a0<\/p>\n<p>[50] Ver Folios 242-244 del \u00a0 Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[51] Sentencia \u00a0 T-281 de 2016, T-370 de 2017, entre otros. \u00a0 \u00a0<\/p>\n<p>[52] \u00c9nfasis \u00a0 agregado. \u00a0 \u00a0<\/p>\n<p>[53] Sentencia \u00a0 T-281 de 2016, T-273 de 2018, entre otras. Por ejemplo, en el fallo T-281 de \u00a0 2016 se afirma \u201cen la sentencia T-730 de 2012, la Corte reiter\u00f3 que para \u00a0 efectos determinar la invalidez de una persona, el juez de tutela puede recurrir \u00a0 al acervo probatorio que reposa en el expediente. De manera que si se allegan \u00a0 documentos diferentes al dictamen de p\u00e9rdida de capacidad laboral que prueben la \u00a0 invalidez, por ejemplo, un dictamen de medicina legal o una sentencia de \u00a0 interdicci\u00f3n, \u00e9stos deber\u00e1n ser tenidos como pruebas v\u00e1lidas de la situaci\u00f3n de \u00a0 invalidez. En caso contrario, se desconocer\u00eda la obligaci\u00f3n de prestar una \u00a0 protecci\u00f3n especial a las personas que se encuentran en situaci\u00f3n de debilidad \u00a0 manifiesta\u201d \u00a0 \u00a0<\/p>\n<p>[54] En el \u00a0 presente ac\u00e1pite se seguir\u00e1 de cerca la sentencia T-702 de 2014. \u00a0 \u00a0<\/p>\n<p>[55] De acuerdo al \u00a0 art\u00edculo 41 de la Ley 100 de 1993 \u201cCorresponde al Instituto de Seguros \u00a0 Sociales, Administradora Colombiana de Pensiones -COLPENSIONES-, a las \u00a0 Administradoras de Riesgos Profesionales\u00a0&#8211; ARP-, a las Compa\u00f1\u00edas de Seguros que \u00a0 asuman el riesgo de\u00a0invalidez\u00a0y muerte, y a las Entidades Promotoras de Salud \u00a0 EPS, determinar en una primera oportunidad la p\u00e9rdida de capacidad laboral y \u00a0 calificar el grado de\u00a0invalidez\u00a0y el origen de estas contingencias.\u201d M\u00e1s \u00a0 adelante esta disposici\u00f3n se\u00f1ala a las Juntas Regionales y a la Junta Nacional \u00a0 de Calificaci\u00f3n como entidades a las cuales se puede apelar para solicitar la \u00a0 revisi\u00f3n de dichos ex\u00e1menes. \u00a0 \u00a0<\/p>\n<p>[56] La sentencia \u00a0 T-702 de 2014 tambi\u00e9n refiere que \u201cuna excepci\u00f3n a esta primera regla se \u00a0 deriva de la solicitud elevada por una persona que requiera la calificaci\u00f3n para \u00a0 acceder a beneficios cajas de compensaci\u00f3n familiar, entidades promotoras de \u00a0 salud, administradoras del r\u00e9gimen subsidiado o para acceder al subsidio del \u00a0 Fondo de Solidaridad Pensional y a los beneficios de la Ley 361 de 1997.\u201d. \u00a0 \u00a0<\/p>\n<p>[57] Art\u00edculos 4 del Decreto 917 de 1999, y 28 \u00a0 del Decreto 2463 de 2001. \u00a0 \u00a0<\/p>\n<p>[58] El fallo \u00a0 T-702 de 2014 explica al respecto: \u201cEl art\u00edculo 41 de la Ley 100 de 1993 \u00a0 dispone que los dict\u00e1menes que adopten las Juntas de Calificaci\u00f3n deben \u00a0 \u201ccontener expresamente los fundamentos de hecho y de derecho que dieron origen a \u00a0 esta decisi\u00f3n\u201d. Los fundamentos de hecho son todos aquellos que se relacionan \u00a0 con la ocurrencia de determinada contingencia, lo cual incluye historias \u00a0 cl\u00ednicas, reportes, valoraciones o ex\u00e1menes m\u00e9dicos peri\u00f3dicos; y en general, \u00a0 los que puedan servir de prueba para certificar una determinada relaci\u00f3n causal, \u00a0 tales como certificado de cargos y labores, comisiones, realizaci\u00f3n de \u00a0 actividades, subordinaci\u00f3n, uso de determinadas herramientas, aparatos, equipos \u00a0 o elementos, contratos de trabajo, estad\u00edsticas o testimonios, entre otros, que \u00a0 se relacionen con la patolog\u00eda, lesi\u00f3n o condici\u00f3n en estudio. Respecto de los \u00a0 fundamentos de derecho, se trata de todas las normas que se aplican al caso de \u00a0 que se trate.\u201d \u00a0 \u00a0<\/p>\n<p>[59] \u201cARTICULO \u00a0 3o. FECHA DE ESTRUCTURACI\u00d3N O DECLARATORIA DE LA P\u00c9RDIDA DE LA CAPACIDAD \u00a0 LABORAL. Es la fecha en que se genera en el individuo una p\u00e9rdida en su \u00a0 capacidad laboral en forma permanente y definitiva. Para cualquier contingencia, \u00a0 esta fecha debe documentarse con la historia cl\u00ednica, los ex\u00e1menes cl\u00ednicos y de \u00a0 ayuda diagn\u00f3stica, y puede ser anterior o corresponder a la fecha de \u00a0 calificaci\u00f3n.\u201d En concordancia con los art\u00edculos 11, \u00a0 35 y 40\u00a0del Decreto 2463 de 2001. \u00a0 \u00a0<\/p>\n<p>[60] Actualmente, \u00a0 el Manual \u00fanico para la mencionada calificaci\u00f3n se rige por el Decreto 1507 de \u00a0 2014 que al respecto refiere: \u201cFecha de estructuraci\u00f3n: Se \u00a0 entiende como la fecha en que una persona pierde un grado o porcentaje de su \u00a0 capacidad laboral u ocupacional, de cualquier origen, como consecuencia de una \u00a0 enfermedad o accidente, y que se determina con base en la evoluci\u00f3n de las \u00a0 secuelas que han dejado estos. Para el estado de invalidez, esta fecha debe ser \u00a0 determinada en el momento en el que la persona evaluada alcanza el cincuenta por \u00a0 ciento (50%) de p\u00e9rdida de la capacidad laboral u ocupacional. Esta fecha \u00a0 debe soportarse en la historia cl\u00ednica, los ex\u00e1menes cl\u00ednicos y de ayuda \u00a0 diagn\u00f3stica y puede ser anterior o corresponder a la fecha de la \u00a0 declaratoria de la p\u00e9rdida de la capacidad laboral. Para aquellos casos en los \u00a0 cuales no exista historia cl\u00ednica, se debe apoyar en la historia natural de la \u00a0 enfermedad. En todo caso, esta fecha debe estar argumentada por el calificador y \u00a0 consignada en la calificaci\u00f3n. Adem\u00e1s, no puede estar sujeta a que el \u00a0 solicitante haya estado laborando y cotizando al Sistema de Seguridad Social \u00a0 Integral.\u201d \u00c9nfasis agregado. \u00a0 \u00a0<\/p>\n<p>[61] Sentencias T-859 de 2004 y T-595 de 2006. \u00a0 \u00a0<\/p>\n<p>[62] En el \u00a0 expediente se incluye copia del Acuerdo No. II de la Junta Directiva del \u00a0 Instituto del Seguro Social de Santander aprobado el 26 de julio de 1991, \u00a0 mediante el cual autoriza atenci\u00f3n m\u00e9dica a la se\u00f1ora Blanca Patricia Goyeneche \u00a0 Calder\u00f3n en condici\u00f3n de hija con discapacidad. Ver folio 22 del Cuaderno \u00a0 Principal. Adem\u00e1s, en los dict\u00e1menes practicados a la actora que nunca ha \u00a0 trabajado y no se registra ning\u00fan antecedente laboral. \u00a0 Ver Folios 32-37 y 135 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[63] Sentencia \u00a0 T-281 de 2016, T-273 de 2018, entre otras. Por ejemplo, en el fallo T-281 de \u00a0 2016 se afirma \u201cen la sentencia T-730 de 2012, la Corte reiter\u00f3 que para \u00a0 efectos determinar la invalidez de una persona, el juez de tutela puede recurrir \u00a0 al acervo probatorio que reposa en el expediente. De manera que si se allegan \u00a0 documentos diferentes al dictamen de p\u00e9rdida de capacidad laboral que prueben la \u00a0 invalidez, por ejemplo, un dictamen de medicina legal o una sentencia de \u00a0 interdicci\u00f3n, \u00e9stos deber\u00e1n ser tenidos como pruebas v\u00e1lidas de la situaci\u00f3n de \u00a0 invalidez. En caso contrario, se desconocer\u00eda la obligaci\u00f3n de prestar una \u00a0 protecci\u00f3n especial a las personas que se encuentran en situaci\u00f3n de debilidad \u00a0 manifiesta\u201d \u00a0 \u00a0<\/p>\n<p>[64] Sentencia \u00a0 T-334 de 2019. \u00a0 \u00a0<\/p>\n<p>[65] Aunque el \u00a0 dictamen se\u00f1ala expresamente \u201cse establece como fecha de estructuraci\u00f3n \u00a0 corresponde a la fecha de la presente calificaci\u00f3n 26\/09\/2018 (sic)\u201d, la \u00a0 Corte advierte que la fecha del dictamen no fue el 26 de septiembre sino el 27 \u00a0 de septiembre. Ver Folios 242-244 del Cuaderno \u00a0 Principal. \u00a0 \u00a0<\/p>\n<p>[66] Ver Folio 28 \u00a0 del Cuaderno Principal. Textualmente la certificaci\u00f3n m\u00e9dica expedida por el \u00a0 galeno tratante indic\u00f3 al respecto: \u201cPor medio del presente certific\u00f3 que \u00a0 desde hace varios a\u00f1os vengo prestando mis servicios profesionales a la paciente \u00a0 Blanca Patricia Goyeneche quien presenta trastorno psic\u00f3tico cr\u00f3nico y \u00a0 epilepsia, ambas enfermedades altamente incapacitantes y de curso cr\u00f3nico que le \u00a0 impiden valerse por s\u00ed misma y requiere protecci\u00f3n permanente\u201d. \u00a0 \u00a0<\/p>\n<p>[67] Ver Folio 51 \u00a0 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[68] Ver Folio \u00a0 32-37 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[69] Copia del \u00a0 registro civil de nacimiento de Blanca Patricia Goyeneche Calder\u00f3n, en el que se \u00a0 registra que su progenitora es Elvia Calder\u00f3n. Ver folio 46 del Cuaderno \u00a0 Principal. \u00a0 \u00a0<\/p>\n<p>[70] Ver Folio 135 \u00a0 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[71] Ver Folio 51 \u00a0 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[72] Ver Folio 22 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[73] Ver Folios 51 \u00a0 y 135 del Cuaderno Principal. \u00a0 \u00a0<\/p>\n<p>[74] Sentencia \u00a0 T-281 de 2016, T-273 de 2018, entre otras. Por ejemplo, en el fallo T-281 de \u00a0 2016 se afirma \u201cen la sentencia T-730 de 2012, la Corte reiter\u00f3 que para \u00a0 efectos determinar la invalidez de una persona, el juez de tutela puede recurrir \u00a0 al acervo probatorio que reposa en el expediente. De manera que si se allegan \u00a0 documentos diferentes al dictamen de p\u00e9rdida de capacidad laboral que prueben la \u00a0 invalidez, por ejemplo, un dictamen de medicina legal o una sentencia de \u00a0 interdicci\u00f3n, \u00e9stos deber\u00e1n ser tenidos como pruebas v\u00e1lidas de la situaci\u00f3n de \u00a0 invalidez. En caso contrario, se desconocer\u00eda la obligaci\u00f3n de prestar una \u00a0 protecci\u00f3n especial a las personas que se encuentran en situaci\u00f3n de debilidad \u00a0 manifiesta\u201d \u00a0 \u00a0<\/p>\n<p>[75] Sentencia T-334 de 2019. \u00a0 \u00a0<\/p>\n<p>[76] Sentencias T-730 de 2012 y \u00a0 T-370 de 2017. \u00a0 \u00a0<\/p>\n<p>[77] M.P. \u00a0 Alberto Rojas R\u00edos. \u00a0 \u00a0<\/p>\n<p>[78] Consideraciones de la Corte, cap\u00edtulo 4, supra. \u00a0 \u00a0<\/p>\n<p>[79] Sentencia C-408 de 1994. M.P. \u00a0 Fabio Mor\u00f3n D\u00edaz: \u201cNo resulta contraria al esp\u00edritu de la Constituci\u00f3n esta \u00a0 disposici\u00f3n [Ley 100, Art.44], pues se trata de evitar fraudes al sistema \u00a0 de pensi\u00f3n de invalidez o por lo menos de controlar la real circunstancia de \u00a0 permanencia en invalidez de sus beneficiarios. Cumplir estas medidas, salvo los \u00a0 casos de fuerza mayor,\u00a0 le impone una carga al interesado, completamente \u00a0 leg\u00edtima, toda vez que dentro de los deberes de los ciudadanos est\u00e1 el de \u00a0 contribuir al financiamiento de los gastos e inversiones del Estado dentro de \u00a0 conceptos de justicia y equidad (art. 95-9\u00a0 C.N.). De otra parte, es claro \u00a0 que el servicio p\u00fablico, puede ser oneroso tal como lo prev\u00e9 la propia Carta en \u00a0 su art\u00edculo 367, sin exonerar de esa posibilidad a la seguridad social\u201d. \u00a0 \u00a0<\/p>\n<p>[80] Al respecto \u00a0 ver, principalmente, la Sentencia C-072 de 2003. M.P. Alfredo Beltr\u00e1n Sierra. \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0T-524-19 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 Sentencia \u00a0 T-524\/19 \u00a0 \u00a0 ACCION DE TUTELA PARA RECONOCIMIENTO DE \u00a0 PENSION DE SOBREVIVIENTES A HIJO EN SITUACION DE DISCAPACIDAD-Procedencia \u00a0 excepcional por ser el mecanismo id\u00f3neo \u00a0 \u00a0 DERECHO A LA \u00a0 PENSION DE SOBREVIVIENTES PARA HIJO EN SITUACION DE DISCAPACIDAD-Requisitos \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126],"tags":[],"class_list":["post-26915","post","type-post","status-publish","format-standard","hentry","category-tutelas-2019"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/26915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=26915"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/26915\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=26915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=26915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=26915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}