{"id":27465,"date":"2024-07-02T20:38:12","date_gmt":"2024-07-02T20:38:12","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/07\/02\/t-267-21\/"},"modified":"2024-07-02T20:38:12","modified_gmt":"2024-07-02T20:38:12","slug":"t-267-21","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-267-21\/","title":{"rendered":"T-267-21"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia T-267\/21 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Improcedencia por falta de relevancia constitucional y no evidenciar afectaci\u00f3n de derechos fundamentales \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(\u2026) los argumentos expuestos por el actor, m\u00e1s all\u00e1 de exponer una cuesti\u00f3n iusfundamental, evidencian una discusi\u00f3n de orden legal y ante todo de evidente y claro contenido econ\u00f3mico. (\u2026), con el recurso de amparo el accionante pretende agotar una instancia judicial adicional al proceso de controversias contractuales. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>RELEVANCIA CONSTITUCIONAL-Finalidad \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Relevancia constitucional como requisito de procedibilidad \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(\u2026) implica la verificaci\u00f3n de -al menos tres- elementos. Por una parte, que la controversia exponga una cuesti\u00f3n constitucional y no un debate meramente legal o de contenido econ\u00f3mico. En segundo lugar, que el debate planteado involucre el contenido, alcance y goce de un derecho fundamental. Finalmente, que no se trate del agotamiento de una instancia adicional al proceso ordinario. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Referencia: Expediente T-8.121.591 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Acci\u00f3n de tutela instaurada por N\u00e9stor Alfonso Guti\u00e9rrez Romero contra la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Magistrado ponente: \u00a0<\/p>\n<p>JOS\u00c9 FERNANDO REYES CUARTAS\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Bogot\u00e1 D.C., once (11) de agosto de dos mil veintiuno (2021). \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La Sala Octava de Revisi\u00f3n de tutelas de la Corte Constitucional, integrada por la magistrada Diana Fajardo Rivera y los magistrados Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas, quien la preside, en ejercicio de sus competencias constitucionales y legales, profiere la siguiente \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Dentro del tr\u00e1mite de revisi\u00f3n de los fallos del 24 de septiembre y 24 de noviembre de 2020, proferidos por las Subsecciones A y B de la Secci\u00f3n Tercera del Consejo de Estado, en primera y segunda instancia, respectivamente. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>I. ANTECEDENTES \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El se\u00f1or N\u00e9stor Alfonso Guti\u00e9rrez Romero, actuando en nombre propio, instaur\u00f3 acci\u00f3n de tutela contra la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca, con el objetivo de obtener la protecci\u00f3n de los derechos a la igualdad y al debido proceso. Para sustentar la solicitud de amparo narr\u00f3 los siguientes: \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Hechos \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El actor explic\u00f3 que el abogado Camilo Arciniegas Andrade suscribi\u00f3 con Inravisi\u00f3n dos contratos de prestaci\u00f3n de servicios. Ambos ten\u00edan por objeto ejercer la defensa de la entidad en tr\u00e1mites judiciales en los que figuraba como demandada. Por una parte, el contrato 407 (suscrito el 19 de octubre de 1994) en el proceso de reparaci\u00f3n directa instaurado por Israel Camargo y otros. En segundo lugar, el contrato 099 (suscrito el 2 de mayo de 1996) en el proceso de nulidad y restablecimiento del derecho instaurado por Antenas de Colombia Ltda. (en adelante Antecol). \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El accionante se\u00f1al\u00f3 que el 28 de septiembre de 2000, por escrito y con autorizaci\u00f3n de Inravisi\u00f3n, el abogado Camilo Arciniegas Andrade le cedi\u00f3 los dos contratos. Seg\u00fan el demandante, los dos documentos fueron firmados por el cedente, el cesionario y el presidente de Inravisi\u00f3n. Sin embargo, el actor afirm\u00f3 que en el documento de cesi\u00f3n del contrato 099 de 1996, el abogado Arciniegas Andrade no anot\u00f3 el n\u00famero de su c\u00e9dula y se repiti\u00f3 por error la p\u00e1gina 2 del contrato 407 de 1994. En criterio del demandante, ninguna de las circunstancias descritas desvirtu\u00f3 la existencia de la cesi\u00f3n del contrato. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El demandante afirm\u00f3 que el 3 de noviembre de 2000, mientras se ejecutaba la cesi\u00f3n del contrato 099 de 1996, el representante legal de Inravisi\u00f3n le otorg\u00f3 poder para ejercer la defensa de la entidad en el mismo proceso promovido por Antecol, cuyo tr\u00e1mite se surt\u00eda ante el Consejo de Estado. Seg\u00fan el actor, represent\u00f3 a Inravisi\u00f3n durante m\u00e1s de doce a\u00f1os. Durante ese periodo rindi\u00f3 informes mensuales hasta cuando fue suprimido el Instituto y continu\u00f3 rindi\u00e9ndoselos a la entidad que recibi\u00f3 dichos procesos: Radio Televisi\u00f3n Nacional de Colombia (en adelante RTVC). El demandante agreg\u00f3 que, debido a que Inravisi\u00f3n fue liquidada, el apoderado general y el representante legal de la Fiduciaria La Previsora S.A. confirm\u00f3 el poder otorgado al accionante. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El actor manifest\u00f3 que, en sentencia del 29 de julio de 2013, la Subsecci\u00f3n B de la Secci\u00f3n Tercera del Consejo de Estado neg\u00f3 las pretensiones de la demanda promovida por Antecol contra Inravisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El demandante consider\u00f3 que, como consecuencia de lo anterior, se hizo exigible el pago de la remuneraci\u00f3n pactada en la cl\u00e1usula tercera del contrato de prestaci\u00f3n de servicios 099 de 1996 (el contrato del que se considera cesionario). Seg\u00fan esta, cuando \u201cpor sentencia definitiva fuere denegada la indemnizaci\u00f3n pedida por ANTECOL LTDA., [al apoderado le corresponder\u00eda] un diez (10%) por ciento de su valor actual calculado en salarios m\u00ednimos legales mensuales\u201d0F1. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 31 de octubre de 2013 y el 27 de octubre de 2014, el accionante present\u00f3 ante el Ministerio de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones (en adelante MinTic) la documentaci\u00f3n necesaria para obtener el pago de los honorarios causados. No obstante, mediante oficio del 29 de octubre de 2014, el jefe de la Oficina Jur\u00eddica del Ministerio objet\u00f3 el cobro porque exist\u00eda \u201cuna inconsistencia en la cesi\u00f3n del contrato, ya que esta constaba de dos folios, en el primero de los cuales se expresaba cederse el contrato 099, mientras que el segundo folio -donde est\u00e1n las firmas- se refer\u00eda al contrato 407\u201d1F2. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El actor instaur\u00f3 demanda de controversias contractuales contra el acto administrativo expedido por el MinTic. El objetivo era obtener las siguientes declaraciones. Por una parte, la existencia del contrato 099 de 1996 celebrado entre Inravisi\u00f3n y el abogado Camilo Arciniegas Andrade. En segundo lugar, la existencia de la cesi\u00f3n del referido contrato a su nombre. Esta se realiz\u00f3 mediante documento del 28 de septiembre de 2000. Finalmente, que se caus\u00f3 a su favor la remuneraci\u00f3n pactada en la cl\u00e1usula tercera del contrato, y, como consecuencia, se condenara a la entidad a pagarle la cuota de \u00e9xito estipulada. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En sentencia de 25 de junio de 2018, el Juzgado 31 Administrativo de Bogot\u00e1 declar\u00f3 el incumplimiento del contrato de prestaci\u00f3n de servicios 099 por parte de la entidad. Como consecuencia, conden\u00f3 a la entidad a pagarle al demandante la cuota de \u00e9xito. Contra esa decisi\u00f3n las partes interpusieron recurso de apelaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Subsecci\u00f3n A de la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca decidi\u00f3 la apelaci\u00f3n. En fallo del 13 de febrero de 2020, revoc\u00f3 lo decidido por el a quo y neg\u00f3 las pretensiones de la demanda. Seg\u00fan el actor, la segunda instancia consider\u00f3 que no se acredit\u00f3 la existencia de la cesi\u00f3n del contrato porque no hab\u00eda prueba de la manifestaci\u00f3n de aceptaci\u00f3n expresa por parte de Inravisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En criterio del accionante, la sentencia de segunda instancia emitida por el tribunal incurri\u00f3 en los defectos f\u00e1ctico, violaci\u00f3n directa de la Constituci\u00f3n y desconocimiento del precedente. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En relaci\u00f3n con el defecto f\u00e1ctico, el demandante explic\u00f3 que en el fallo impugnado no se efectu\u00f3 una valoraci\u00f3n conjunta de las pruebas de manera que se vulner\u00f3 el art\u00edculo 176 del CGP. Espec\u00edficamente, el actor sostuvo que la segunda instancia apreci\u00f3 de manera aislada el documento de cesi\u00f3n del contrato. Adem\u00e1s, el accionante se\u00f1al\u00f3 que el an\u00e1lisis se circunscribi\u00f3 a determinar si la mencionada cesi\u00f3n hab\u00eda surtido efectos jur\u00eddicos. El actor agreg\u00f3 que la decisi\u00f3n del tribunal desconoci\u00f3 el principio de indivisibilidad de la prueba resultante del documento p\u00fablico (art\u00edculo 250 del CGP) porque el estudio se limit\u00f3 a la parte enunciativa del contrato y no a la dispositiva. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De otra parte, el accionante argument\u00f3 que el ad quem distorsion\u00f3 el contenido de la demanda a partir de un error de digitaci\u00f3n en las p\u00e1ginas del documento de la cesi\u00f3n del contrato 099 de 1996. Ello ocurri\u00f3 pese a que se aportaron pruebas que subsanaban el yerro. El actor sostuvo que el tribunal apreci\u00f3 indebidamente el poder otorgado por Inravisi\u00f3n para el proceso objeto del contrato 099 de 1996 en el que se acreditaba -en su opini\u00f3n- que \u201clas partes entendieron firmar la cesi\u00f3n del contrato 099\u201d2F3. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Adem\u00e1s, el accionante se\u00f1al\u00f3 que la sentencia de segunda instancia no tuvo en cuenta las siguientes pruebas. En primer lugar, la p\u00f3liza de cumplimiento del contrato 099 de 1996. Esta fue aceptada por Inravisi\u00f3n de manera que -en su criterio- acreditaba que la entidad y el cesionario entendieron firmar la cesi\u00f3n de ese contrato. En segundo lugar, los informes rendidos durante doce a\u00f1os por el accionante (en calidad de cesionario) sobre el proceso ordinario objeto del contrato 099 de 1996. Finalmente, la declaraci\u00f3n del abogado Arciniegas Andrade (en calidad de cedente del contrato) quien afirm\u00f3 que cedi\u00f3 al actor el contrato 099 de 1996. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Respecto de la violaci\u00f3n directa de la Constituci\u00f3n, el actor argument\u00f3 que la decisi\u00f3n que acusa no aplic\u00f3 tanto los art\u00edculos 13 y 83 de la Carta como el art\u00edculo 45 del CPACA. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Sobre el desconocimiento del precedente, el accionante explic\u00f3 que la sentencia pretermiti\u00f3 lo establecido en los fallos T-475 de 1992 de la Corte Constitucional y del 18 de febrero de 2010 del Consejo de Estado. Seg\u00fan estos precedentes: \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201c(\u2026) act\u00faa de mala fe la entidad que, en ejecuci\u00f3n de la cesi\u00f3n de un contrato, confiere un poder, lo confirma, pide informes al apoderado y despu\u00e9s, a la hora de cumplir por haberse realizado a cabalidad el objeto de contrato, pretexta ladinamente que hab\u00eda aceptado la cesi\u00f3n de otro contrato. La Subsecci\u00f3n A no pod\u00eda convalidar semejante conducta. Le bastaba con aplicar el principio constitucional de la buena fe. El art\u00edculo 45 del CPACA, que impone a las autoridades el deber de corregir en cualquier tiempo los errores formales, no es m\u00e1s que la aplicaci\u00f3n de este principio supremo a las actuaciones administrativas\u201d3F4. \u00a0<\/p>\n<p>1. Con base en lo expuesto, el demandante solicit\u00f3 a la Corte proteger sus derechos fundamentales \u201cinvalidando la sentencia de la Subsecci\u00f3n A. Con todo respeto, pido que resuelva directamente de fondo, pues la Subsecci\u00f3n A qued\u00f3 impedida para hacerlo, por su manifiesta animadversi\u00f3n y sesgo contra el suscrito\u201d4F5. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sentencia objeto de la acci\u00f3n de tutela \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En sentencia del 13 de febrero de 2020, la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca decidi\u00f3 los recursos de apelaci\u00f3n presentados por las partes contra el fallo del 25 de junio de 2018, proferido por el Juzgado 31 Administrativo de Bogot\u00e1, que accedi\u00f3 a las pretensiones de la demanda. El tribunal plante\u00f3 como problema jur\u00eddico: \u201c\u00bfsi el acuerdo de voluntades realizado entre el se\u00f1or CAMILO ARCINIEGAS ANDRADE y el se\u00f1or N\u00c9STOR ALFONSO GUTI\u00c9RREZ ROMERO, surti\u00f3 los efectos jur\u00eddicos para considerarla como una cesi\u00f3n del contrato de prestaci\u00f3n de servicios 009 de 2 de mayo de 1996?\u201d5F6. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Subsecci\u00f3n A hizo referencia a las pruebas aportadas al proceso. Entre ellas destac\u00f3 el contrato de prestaci\u00f3n de servicios 099 de 1996. Este fue celebrado entre Inravisi\u00f3n y el abogado Camilo Arciniegas Andrade con el objeto de que este \u00faltimo representara los intereses de la entidad dentro del proceso iniciado por Antecol. En dicho convenio se estableci\u00f3 una cuota de \u00e9xito del 10% de las pretensiones en caso de que fueren denegadas en sentencia definitiva. Asimismo, se pact\u00f3 expresamente que no se pod\u00eda ceder el contrato sin la autorizaci\u00f3n previa y expresa de Inravisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Secci\u00f3n Tercera refiri\u00f3 que el documento del 28 de septiembre de 2000 conten\u00eda la cesi\u00f3n del contrato de prestaci\u00f3n de servicios del abogado Arciniegas Andrade a N\u00e9stor Alfonso Guti\u00e9rrez Romero. Sin embargo, el ad quem resalt\u00f3 que, en la segunda p\u00e1gina donde aparec\u00edan las firmas de las partes, el documento se refer\u00eda al contrato 407 de 1994. A efecto de subsanar esta inconsistencia, el juez solicit\u00f3 a la Aseguradora Confianza la copia de la cesi\u00f3n del contrato. No obstante, la compa\u00f1\u00eda inform\u00f3 que esta no reposaba en sus bases de datos. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El tribunal refiri\u00f3 que el 3 de noviembre de 2000, Inravisi\u00f3n le otorg\u00f3 poder al accionante para que agenciara los intereses de la entidad dentro del mismo proceso instaurado por Antecol. Finalmente, en el ac\u00e1pite de pruebas, la autoridad judicial mencion\u00f3 que se incorpor\u00f3 al expediente una constancia expedida por el abogado Arciniegas Andrade en la que este afirm\u00f3 que existi\u00f3 la cesi\u00f3n del contrato 099 de 1996. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Con el fin de resolver la cuesti\u00f3n planteada, la Subsecci\u00f3n A aludi\u00f3 a los art\u00edculos 888 del C.Co, 9 y 41 de la Ley 80 de 1993, a la jurisprudencia del Consejo de Estado6F7 y de la Corte Suprema de Justicia7F8. Con base en esos fundamentos, determin\u00f3 que el negocio jur\u00eddico de cesi\u00f3n de contratos estatales exige el cumplimiento de formalidades (i.e. la autorizaci\u00f3n expresa, previa y por escrito por parte de la entidad estatal) de manera que si estas no se satisfacen, la cesi\u00f3n se considera inexistente. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Secci\u00f3n Tercera estableci\u00f3 que en el asunto sub examine no estaba demostrada la cesi\u00f3n del contrato de prestaci\u00f3n de servicios 099 de 1996 porque no hab\u00eda manifestaci\u00f3n de la aceptaci\u00f3n expresa por parte de Inravisi\u00f3n (hoy MinTic). En ese sentido, el tribunal explic\u00f3 que la primera hoja del documento de cesi\u00f3n del contrato hac\u00eda referencia al contrato 099 de 1996. Sin embargo, la segunda p\u00e1gina -que conten\u00eda las firmas- se refer\u00eda al contrato 407 de 1994. Para el tribunal, dicha inconsistencia afectaba la validez de la cesi\u00f3n, es decir, no acreditaba su existencia. El ad quem a\u00f1adi\u00f3 que el poder que posteriormente le otorg\u00f3 Inravisi\u00f3n al actor tampoco acredit\u00f3 la cesi\u00f3n del contrato 099 de 1996. Esto por cuanto se trat\u00f3 de una actuaci\u00f3n posterior, con base en la cual el accionante present\u00f3 un memorial ante el Consejo de Estado, en calidad de apoderado de la entidad. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por lo anterior, la Subsecci\u00f3n A concluy\u00f3 que en el presente caso no se acredit\u00f3 la cesi\u00f3n del contrato y ninguno de los documentos adicionales aportados reemplazaban la formalidad (cesi\u00f3n expresa, previa y escrita) exigida. En consecuencia, revoc\u00f3 lo decidido por el a quo y, en su lugar, neg\u00f3 las pretensiones de la demanda. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Tr\u00e1mite procesal de la acci\u00f3n de tutela \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Mediante auto del 4 de septiembre de 2020, la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Consejo de Estado admiti\u00f3 la acci\u00f3n de tutela. Adem\u00e1s, orden\u00f3 notificar a los magistrados de la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca y a la ministra de las tecnolog\u00edas de la informaci\u00f3n y las comunicaciones con el prop\u00f3sito de que rindieran el informe del Decreto 2591 de 1991. Asimismo, el juez de primera instancia orden\u00f3 notificar a la Agencia Nacional de Defensa Jur\u00eddica del Estado. Finalmente, pidi\u00f3 el expediente ordinario como medio de prueba. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Contestaci\u00f3n de la tutela \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El Tribunal Administrativo de Cundinamarca pidi\u00f3 que se declarara la improcedencia de la acci\u00f3n o, en su defecto, se negaran las pretensiones. La Subsecci\u00f3n A argument\u00f3 que el accionante pretend\u00eda utilizar la tutela como una instancia adicional del proceso ordinario. Adem\u00e1s, indic\u00f3 que el asunto no ten\u00eda relevancia constitucional. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Secci\u00f3n Tercera explic\u00f3 que no distorsion\u00f3 el objeto de la demanda. Su actuaci\u00f3n se circunscribi\u00f3 a resolver los puntos de la apelaci\u00f3n. Entre estos se cuestion\u00f3 el perfeccionamiento de la cesi\u00f3n del contrato de prestaci\u00f3n de servicios 099 de 1996. En ese contexto, se valor\u00f3 si existi\u00f3 efectivamente la cesi\u00f3n del contrato. Esto no implic\u00f3 una omisi\u00f3n o inadecuada valoraci\u00f3n de las pruebas. En otras palabras, el tribunal se\u00f1al\u00f3 que la cesi\u00f3n del contrato que pretend\u00eda hacer cumplir el demandante no reun\u00eda la solemnidad exigida en el ordenamiento jur\u00eddico para predicar su existencia, esto es, la manifestaci\u00f3n expresa por parte de la entidad p\u00fablica de aceptar la cesi\u00f3n del contrato estatal.\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Sobre la firma de la cesi\u00f3n del contrato de prestaci\u00f3n de servicios 099 de 1996, el tribunal explic\u00f3 que las firmas de la p\u00e1gina 2 del referido documento se refer\u00edan a otro contrato. Adem\u00e1s, exist\u00eda una contradicci\u00f3n por cuanto se repet\u00eda la cl\u00e1usula tercera en la p\u00e1gina uno y en la p\u00e1gina dos. Sin embargo, en una de las p\u00e1ginas se hac\u00eda referencia al contrato 099 de 1996 mientras que en la otra al contrato 407 de 1994. Por ello, en la sentencia acusada, la Secci\u00f3n Tercera concluy\u00f3 que no estaba demostrada la aceptaci\u00f3n expresa de la entidad respecto de la cesi\u00f3n del contrato 099 de 1996. Adem\u00e1s, en el curso del proceso la propia entidad estatal manifest\u00f3 que no ten\u00eda en sus archivos la referida cesi\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El tribunal se\u00f1al\u00f3 que el accionante alleg\u00f3 otras pruebas tendientes a demostrar que represent\u00f3 a Inravisi\u00f3n. Sin embargo, para la Secci\u00f3n Tercera, la ausencia de la aceptaci\u00f3n expresa y las solemnidades propias de la cesi\u00f3n del contrato no pod\u00edan ser subsanadas con otro tipo de medios probatorios o con la conducta de las partes. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sentencia de primera instancia \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En sentencia del 24 de septiembre de 2020, la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Consejo de Estado neg\u00f3 el amparo solicitado. El a quo explic\u00f3 que el tribunal valor\u00f3 adecuadamente el documento denominado cesi\u00f3n del contrato 099 de 1996 y concluy\u00f3 que este no reun\u00eda las solemnidades exigidas en la ley sustancial para predicar la existencia de dicho acto. En especial porque no contaba con la aceptaci\u00f3n expresa y escrita por parte de la entidad p\u00fablica sobre la cesi\u00f3n del contrato. La Secci\u00f3n a\u00f1adi\u00f3 que el tribunal advirti\u00f3 que el clausulado y las firmas que aparec\u00edan en la p\u00e1gina 2 del documento se refer\u00edan al contrato 407 de 1994. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En relaci\u00f3n con el defecto por violaci\u00f3n directa de la Constituci\u00f3n, el Consejo de Estado concluy\u00f3 que no se desconoci\u00f3 el principio de la buena fe. En su criterio, se apreci\u00f3 la conducta de la entidad demandada que, ante la solicitud de pago del actor, \u201cintent\u00f3 verificar la existencia de la referida cesi\u00f3n contractual, incluso requiri\u00f3 a la aseguradora, quien se\u00f1al\u00f3, que no ten\u00eda este documento\u201d8F9. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Asimismo, el juez de tutela se\u00f1al\u00f3 que la autoridad judicial accionada reiter\u00f3 los par\u00e1metros fijados por el Consejo de Estado sobre los requisitos para considerar la existencia de la cesi\u00f3n de un contrato estatal (i.e la autorizaci\u00f3n previa y por escrito por parte de la entidad)9F10. En esa medida, el a quo ratific\u00f3 la conclusi\u00f3n del tribunal. Seg\u00fan esta, el demandante no pod\u00eda argumentar un presunto error de transcripci\u00f3n en el documento de cesi\u00f3n de contrato para afirmar que cumpli\u00f3 todas las solemnidades establecidas en la ley. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La impugnaci\u00f3n \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El accionante reiter\u00f3 los argumentos plasmados en el escrito inicial. Para el actor, el juez de tutela deb\u00eda \u201cexaminar y valorar el impago de la remuneraci\u00f3n confront\u00e1ndolo con los actos con que la entidad contratante ya le hab\u00eda reconocido al cesionario esta calidad luego de la firma del documento de cesi\u00f3n\u201d10F11. Sin embargo, el demandante afirm\u00f3 que el a quo no tuvo en cuenta \u201clos actos propios de la entidad contratante en relaci\u00f3n con el cesionario, ni hizo la necesaria confrontaci\u00f3n\u201d11F12. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El actor reproch\u00f3 que el Consejo de Estado valorara \u00fanicamente la indagaci\u00f3n que hizo la entidad ante el garante. En su criterio, tambi\u00e9n le correspond\u00eda analizar \u201csi el impago contraven\u00eda o no los actos con los cuales la entidad contratante le hab\u00eda reconocido al cesionario esta calidad y le permit\u00edan confiar en la seriedad de la contrataci\u00f3n\u201d12F13. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para el accionante, el a quo no estudi\u00f3 el defecto f\u00e1ctico. En su criterio, este se limit\u00f3 a transcribir las motivaciones del fallo del tribunal accionado. A partir de ello, determin\u00f3 que la sentencia acusada valor\u00f3 en su integridad el contrato 099 de 1996. El demandante sostuvo que no se dijo nada sobre la indivisibilidad del documento, ni sobre la parte dispositiva de este. Tampoco se pronunci\u00f3 \u201csobre la desacertada regla probatoria que sienta el Tribunal cuando sostiene que la firma de un documento solo refrenda lo dicho en la p\u00e1gina donde aparece estampada\u201d13F14. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Finalmente, el accionante se\u00f1al\u00f3 que el Consejo de Estado \u201cno enmend\u00f3 el error del Tribunal en aseverar que la demanda pretend\u00eda suplir la falta de la formalidad documental de la cesi\u00f3n, pese a que en verdad sosten\u00eda y demostraba que el documento de cesi\u00f3n existe, por m\u00e1s que la entidad contratante hubiera incurrido en un error intrascendente\u201d14F15. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sentencia de segunda instancia \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En sentencia del 24 de noviembre de 2020, la Subsecci\u00f3n B de la Secci\u00f3n Tercera del Consejo de Estado confirm\u00f3 la decisi\u00f3n de primera instancia. Esto por cuanto la autoridad judicial accionada \u201cvalor\u00f3 de manera integral el documento denominado \u2018cesi\u00f3n del contrato No. 099 de 1996\u2019 y adem\u00e1s se pronunci\u00f3 sobre los medios de prueba allegados al proceso, tales como el poder otorgado al actor para la representaci\u00f3n judicial en el proceso No. 1995-01712-00\/01 y un memorial de impulso procesal en el mismo asunto, con el fin de demostrar la existencia de la referida cesi\u00f3n\u201d15F16. El ad quem advirti\u00f3 que, con el objetivo de pronunciarse sobre las pretensiones, era necesario demostrar la existencia y la cesi\u00f3n del contrato. Esto no se acredit\u00f3 en el sub examine pues la cesi\u00f3n no se hizo conforme a las formalidades exigidas en la ley. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Subsecci\u00f3n B mencion\u00f3 que el tribunal valor\u00f3 el documento que conten\u00eda la cesi\u00f3n del contrato 099 de 1996. Adem\u00e1s, encontr\u00f3 que este no contaba con la aceptaci\u00f3n de la cesi\u00f3n por parte de Inravisi\u00f3n pues \u201cde ese documento, se alleg\u00f3 solo la primera hoja, ya que la segunda hoja, en la cual estaban las firmas, pertenec\u00eda a la cesi\u00f3n de un contrato diferente al que era objeto de an\u00e1lisis en ese proceso judicial (contrato No. 407 de 1994)\u201d16F17. La Subsecci\u00f3n B concluy\u00f3 que los argumentos esgrimidos en la impugnaci\u00f3n no ten\u00edan respaldo porque el tribunal no escindi\u00f3 la prueba, sino que valor\u00f3 el documento que conten\u00eda la cesi\u00f3n; esta \u00faltima pertenec\u00eda a dos contratos diferentes. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Adicionalmente, el Consejo de Estado consider\u00f3 que con el escrito de tutela tampoco se aport\u00f3 una prueba que permitiera desvirtuar lo dicho tanto por el juez ordinario como por la primera instancia de tutela sobre la valoraci\u00f3n de la cesi\u00f3n del contrato 099 de 1996. En consecuencia, no se configur\u00f3 el defecto f\u00e1ctico. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Finalmente, el \u00f3rgano de cierre determin\u00f3 que no se desconoci\u00f3 el precedente de la sentencia T-475 de 1992 de la Corte Constitucional. En su criterio, dicho fallo no fij\u00f3 una regla jurisprudencial de unificaci\u00f3n. En todo caso, en aquella decisi\u00f3n se analizaron unos supuestos f\u00e1cticos diferentes a los que son objeto de debate en la presente acci\u00f3n de tutela. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Pruebas que obran en el expediente y actuaciones en sede de revisi\u00f3n\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el expediente digital obra el proceso radicado 2015-00736 contentivo del proceso de controversias contractuales promovido por el accionante contra el MinTic. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En auto del 30 de abril de 2021, la Sala de Selecci\u00f3n n\u00famero cuatro de la Corte Constitucional escogi\u00f3 el presente asunto y fue repartido a este despacho17F18. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>II. CONSIDERACIONES \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Competencia\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Sala Octava de Revisi\u00f3n de la Corte Constitucional es competente para revisar la decisi\u00f3n proferida dentro de la acci\u00f3n de tutela de la referencia, de conformidad con lo dispuesto en los art\u00edculos 86 y 241.9 de la Constituci\u00f3n Pol\u00edtica y en concordancia con los art\u00edculos 31 a 36 del Decreto 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Delimitaci\u00f3n del caso, formulaci\u00f3n del problema jur\u00eddico y esquema de la decisi\u00f3n \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el presente caso, el accionante reclama el reconocimiento de la cesi\u00f3n del contrato de prestaci\u00f3n de servicios 099 de 1994. El objetivo es obtener el reconocimiento y pago de la cuota de \u00e9xito pactada en la cl\u00e1usula tercera de dicho convenio. Seg\u00fan esta, tiene derecho al 10% del valor de la indemnizaci\u00f3n de la que se exoner\u00f3 a la extinta Inravisi\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Revisado el proceso de controversias contractuales que obra en el expediente digital, se destaca que la cesi\u00f3n del contrato 099 de 1994, en la segunda p\u00e1gina contiene la cl\u00e1usula tercera (objeto de la reclamaci\u00f3n) y la cl\u00e1usula tercera y las firmas que convalidan la cesi\u00f3n del contrato 407 de 1994. Lo anterior quiere decir que no existe un documento que contenga la cesi\u00f3n del contrato cuyas p\u00e1ginas uno y dos correspondan al contrato 099 de 1994. Seg\u00fan el accionante, tal yerro fue involuntario y no afect\u00f3 la verdadera intenci\u00f3n de las partes. Esta no era otra que ceder el contrato de prestaci\u00f3n de servicios. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En sentencia del 13 de febrero de 2020, la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca neg\u00f3 las pretensiones del actor porque no exist\u00eda prueba de que la cesi\u00f3n del contrato hubiere sido expresamente aceptada por la entidad contratante. En este sentido, el tribunal descart\u00f3 la apreciaci\u00f3n de otros elementos probatorios para demostrar la cesi\u00f3n del contrato. Esto por cuanto se exige el cumplimiento de formalidades legales no acreditadas en el proceso. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ante la negativa del tribunal, el demandante formul\u00f3 una acci\u00f3n de tutela a trav\u00e9s de la cual pretende que se protejan sus derechos fundamentales y se dicte la sentencia sustitutiva que acceda al petitum de la controversia contractual que plante\u00f3. Para ello, el accionante argument\u00f3 que el error en el documento de cesi\u00f3n del contrato no afect\u00f3 su validez. Adem\u00e1s, alleg\u00f3 pruebas que demostraban la verdadera intenci\u00f3n de la entidad contratante, el contratista y el cesionario. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El actor formul\u00f3 tres cargos. Por una parte, defecto f\u00e1ctico porque el tribunal le dio mayor valor probatorio a la hoja de firmas de la cesi\u00f3n -que correspond\u00eda al contrato 407 de 1994- que a la p\u00e1gina donde se mencionaba la intenci\u00f3n de ceder el contrato 099 de 1996. El demandante agreg\u00f3 que el juez ordinario no valor\u00f3 otros elementos probatorios que demostraban la cesi\u00f3n del contrato (i.e. la constancia del abogado cedente, el poder que le otorg\u00f3 la entidad en el a\u00f1o 2000 para agenciar sus intereses en el mismo proceso de Antecol o el memorial presentado por el accionante como apoderado de Inravisi\u00f3n en el caso Antecol). En segundo lugar, violaci\u00f3n directa de la Constituci\u00f3n por cuanto el tribunal no aplic\u00f3 los art\u00edculos 13 y 83 de la Carta ni el art\u00edculo 45 del CPACA. Finalmente, desconocimiento del precedente porque la sentencia censurada desconoci\u00f3 lo establecido en los fallos T-475 de 1992 de la Corte Constitucional y del 18 de febrero de 2010 del Consejo de Estado. \u00a0 \u00a0<\/p>\n<p>1. Con base en los hechos descritos y en las pruebas que obran en el expediente, le corresponde a la Sala determinar, en primer lugar, si la acci\u00f3n de tutela formulada satisface los requisitos generales de procedencia. En caso de que se habilite el estudio de fondo, la Corte analizar\u00e1 si se configuraron los defectos endilgados a la sentencia del 13 de febrero de 2020 proferida por el Tribunal Administrativo de Cundinamarca. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En la siguiente secci\u00f3n, la Sala Octava de Revisi\u00f3n se referir\u00e1 a la procedencia excepcional de la acci\u00f3n de tutela contra providencias judiciales, despu\u00e9s har\u00e1 referencia a los requisitos generales que habilitan el estudio material del amparo contra decisiones jurisdiccionales y verificar\u00e1 si se cumplen en el caso concreto. Solamente en caso de que la respuesta sea afirmativa, esta corporaci\u00f3n caracterizar\u00e1 los defectos endilgados y estudiar\u00e1 si se configuraron en el asunto sub examine. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La procedencia excepcional de la acci\u00f3n de tutela contra providencias judiciales18F19 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La jurisprudencia constitucional ha sostenido que la acci\u00f3n de tutela procede contra los actos y las decisiones expedidas en ejercicio de la funci\u00f3n jurisdiccional19F20. Se trata del resultado de una lectura arm\u00f3nica de la Constituci\u00f3n con varios instrumentos internacionales de protecci\u00f3n de los derechos humanos20F21. De conformidad con esta: \u201ctoda persona podr\u00e1 hacer uso de mecanismos judiciales \u00e1giles y efectivos que los ampare contra la amenaza o violaci\u00f3n de los derechos fundamentales, aun si esta se causa por quienes act\u00faan en ejercicio de funciones oficiales\u201d21F22. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. A partir de la Sentencia C-543 de 1992, este tribunal admiti\u00f3 la procedencia de la acci\u00f3n de tutela contra providencias judiciales solo en relaci\u00f3n con actuaciones de hecho que impliquen una grave vulneraci\u00f3n a los derechos fundamentales. Posteriormente, la Corte se refiri\u00f3 a la v\u00eda de hecho para abordar el estudio de casos respecto de los cuales se aduce un proceder arbitrario de los jueces que vulnera derechos fundamentales22F23. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La jurisprudencia constitucional tuvo una evoluci\u00f3n en la Sentencia C-590 de 2005. Esta nueva dimensi\u00f3n abandon\u00f3 la expresi\u00f3n v\u00eda de hecho e introdujo los criterios de procedibilidad de la acci\u00f3n de tutela contra decisiones judiciales. Estos presupuestos fueron distinguidos en dos categor\u00edas: i) requisitos generales de procedencia con naturaleza procesal y ii) causales espec\u00edficas de procedibilidad de naturaleza sustantiva. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Criterios generales de procedibilidad de la acci\u00f3n de tutela contra providencias judiciales23F24 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Los requisitos generales de procedencia de la acci\u00f3n de tutela contra providencias judiciales \u201cconstituyen restricciones de \u00edndole procedimental o par\u00e1metros imprescindibles para que el juez de tutela aborde el an\u00e1lisis de fondo\u201d24F25. Estos requisitos exigen: i) que la cuesti\u00f3n sea de relevancia constitucional. En consecuencia, el juez constitucional no puede entrar a estudiar cuestiones que no tienen una clara y marcada importancia constitucional so pena de involucrarse en asuntos que corresponde definir a otras jurisdicciones. Adem\u00e1s, ii) que la persona afectada haya agotado todos los medios ordinarios y extraordinarios de defensa judicial, salvo que se trate de evitar la consumaci\u00f3n de un perjuicio iusfundamental irremediable. iii) Que se acredite el requisito de inmediatez; iv) cuando se trate de una irregularidad procesal, esta tenga la potencialidad de causar un efecto decisivo o determinante en la decisi\u00f3n que se impugna y que afecte los derechos fundamentales de la parte actora; v) que la parte actora identifique de manera razonable los hechos que generaron la afectaci\u00f3n, los derechos vulnerados y que hubiere alegado tal lesi\u00f3n en el proceso judicial (siempre que esto hubiere sido posible); y vi) que no se trate de sentencias de tutela, ni de nulidad por inconstitucionalidad proferidas por el Consejo de Estado25F26. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Requisitos generales de procedencia en el caso concreto \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Como indic\u00f3 la Sala previamente, la procedencia general de la acci\u00f3n tutela contra providencias judiciales est\u00e1 determinada por varios factores26F27. La Corte ha establecido que el estudio de los requisitos gen\u00e9ricos de procedibilidad no es abstracto sino concreto, de all\u00ed que deban verificarse en cada caso. En el presente asunto, esta corporaci\u00f3n abordar\u00e1 inicialmente las exigencias formales y, posteriormente, se referir\u00e1 a las sustanciales27F28. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Legitimaci\u00f3n en la causa28F29. En el asunto sub examine se satisface el requisito de legitimaci\u00f3n en la causa tanto por activa como por pasiva. La acci\u00f3n de tutela fue promovida por el se\u00f1or N\u00e9stor Alfonso Guti\u00e9rrez Romero contra la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca. Esta fue la autoridad judicial que decidi\u00f3 la demanda de controversias contractuales formulada por el actor, quien se considera afectado con la sentencia que neg\u00f3 las pretensiones. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La providencia cuestionada no es una sentencia de tutela ni decide una nulidad por inconstitucionalidad. En el asunto que se examina, la acci\u00f3n de tutela no se dirige contra una decisi\u00f3n de igual naturaleza ni tampoco una sentencia que resolvi\u00f3 una acci\u00f3n de nulidad por inconstitucionalidad, sino contra un fallo proferido por el Tribunal Administrativo de Cundinamarca en el marco de una controversia contractual promovida por el accionante. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Inmediatez. La acci\u00f3n de tutela fue interpuesta dentro de un t\u00e9rmino oportuno y razonable. En efecto, la sentencia objeto de la censura se profiri\u00f3 el 13 de febrero de 2020, fue notificada por correo electr\u00f3nico el 3 de marzo del mismo a\u00f1o y la acci\u00f3n de tutela se radic\u00f3 el 2 de septiembre de 2020; es decir, seis meses despu\u00e9s. \u00a0 \u00a0<\/p>\n<p>1. Identificaci\u00f3n razonable de los hechos que generaron la vulneraci\u00f3n y los derechos vulnerados. Para la Corte esta exigencia se satisface porque el actor identific\u00f3 los hechos que -en su opini\u00f3n- dieron lugar a la afectaci\u00f3n de los derechos a la igualdad y al debido proceso. En efecto, el accionante argument\u00f3 que la vulneraci\u00f3n de las garant\u00edas superiores se configur\u00f3 cuando el tribunal se limit\u00f3 a valorar el documento contentivo de la cesi\u00f3n de contrato 099 de 1996, cuya p\u00e1gina dos -por error- conten\u00eda las firmas de la cesi\u00f3n del contrato 407 de 1994. Para el actor, el error en la p\u00e1gina de las firmas no afect\u00f3 la validez de la cesi\u00f3n y consider\u00f3 que exist\u00edan otros elementos de prueba que permit\u00edan acreditar la intenci\u00f3n de Inravisi\u00f3n de aceptar la cesi\u00f3n del contrato. Adem\u00e1s, el accionante argument\u00f3 que actu\u00f3 de buena fe. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ejercicio subsidiario de la acci\u00f3n de tutela. La Sala Octava encuentra acreditado el requisito de subsidiariedad. En efecto, contra la decisi\u00f3n judicial cuestionada no proceden recursos ante la jurisdicci\u00f3n de lo contencioso administrativo.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En primer lugar, se agotaron los recursos ordinarios porque la sentencia del 13 de febrero de 2020 decidi\u00f3 el recurso de apelaci\u00f3n. En segundo lugar, los defectos descritos no encajan en los presupuestos exigidos para el recurso extraordinario de unificaci\u00f3n de jurisprudencia. Este procede contra la decisi\u00f3n dictada en \u00fanica y segunda instancia por los tribunales administrativos, que \u201ccontrar\u00ede o se oponga a una sentencia de unificaci\u00f3n del Consejo de Estado\u201d29F30. En el presente asunto no se cuestiona el desconocimiento de una decisi\u00f3n de unificaci\u00f3n del \u00f3rgano de cierre, sino aspectos probatorios. Tampoco procede el recurso extraordinario de revisi\u00f3n30F31. Ninguna de las causales previstas en el art\u00edculo 250 del CPACA es prima facie asimilable a alguno de los fundamentos de la acci\u00f3n formulada. En esencia, se insiste, el actor cuestion\u00f3 la valoraci\u00f3n de las pruebas aportadas de cara a la exigencia del cumplimiento de solemnidades en el marco de la cesi\u00f3n de un contrato estatal, lo cual, no habilita la revisi\u00f3n de la sentencia a trav\u00e9s de dicho mecanismo. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Relevancia constitucional \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Corte ha establecido que el objetivo de la acci\u00f3n de tutela contra providencias judiciales es conjurar aquellas situaciones en que la decisi\u00f3n de la autoridad judicial incurre en graves falencias, de relevancia constitucional, que conllevan una decisi\u00f3n incompatible con la Carta31F32. Por tal raz\u00f3n, esta corporaci\u00f3n ha insistido en que es necesario que la petici\u00f3n de amparo plantee una cuesti\u00f3n iusconstitucional y no una de nuda competencia exclusiva del juez natural ordinario32F33. Al respecto, esta Corte ha se\u00f1alado lo siguiente: \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cLa relevancia constitucional tiene como finalidad que el juez constitucional no entre a estudiar cuestiones que carezcan de una clara y marcada importancia constitucional, so pena de involucrarse en asuntos cuya definici\u00f3n es competencia exclusiva del juez ordinario. De esta manera, se garantiza \u201cla \u00f3rbita de acci\u00f3n tanto de los jueces constitucionales, como de los de las dem\u00e1s jurisdicciones\u201d33F34 y, de contera, se erige en garant\u00eda misma de la independencia de los jueces ordinarios \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Segundo, el requisito de la relevancia constitucional busca evitar que, por medio de la acci\u00f3n de tutela contra providencias judiciales, se discutan asuntos legales que, por definici\u00f3n, no le compete resolver al juez de tutela, cuya competencia se limita a aquellos casos en que existan afectaciones o vulneraciones de derechos fundamentales. En otras palabras, este requisito garantiza que la tutela en contra de decisiones judiciales no se convierta en un escenario para controvertir y \u201cdiscutir asuntos de mera legalidad\u201d34F35. La Corte ha sostenido al un\u00edsono que \u201cla definici\u00f3n de asuntos meramente legales o reglamentarios que no tengan una relaci\u00f3n directa con los derechos fundamentales de las partes o que no revistan un inter\u00e9s constitucional claro, no puede ser planteada ante la jurisdicci\u00f3n constitucional.\u201d35F36 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Tercero, el requisito de relevancia constitucional tiene como objetivo evitar que este mecanismo se convierta en una instancia o en un recurso judicial adicional. En este sentido, la Corte ha exigido que \u201cteniendo en cuenta que la tutela contra providencias judiciales no da lugar a una tercera instancia, ni puede reemplazar los recursos ordinarios, es necesario que la causa que origina la presentaci\u00f3n de la acci\u00f3n suponga el desconocimiento de un derecho fundamental\u201d36F37. Solo as\u00ed, la intervenci\u00f3n del juez de tutela, por definici\u00f3n excepcional, no se convierte en una instancia m\u00e1s dentro de los procesos ordinarios\u201d37F38. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De lo anterior, se concluye que -para este tribunal- el requisito de la relevancia constitucional tiene tres finalidades: \u201ci) preservar la competencia y la independencia de los jueces de las jurisdicciones diferentes a la constitucional38F39http:\/\/www.corteconstitucional.gov.co\/relatoria\/2018\/T-422-18.htm &#8211; _ftn28 y, por tanto, evitar que la acci\u00f3n de tutela se utilice para discutir asuntos de mera legalidad39F40http:\/\/www.corteconstitucional.gov.co\/relatoria\/2018\/T-422-18.htm &#8211; _ftn29; ii) restringir el ejercicio de la acci\u00f3n de tutela a cuestiones de relevancia constitucional que afecten los derechos fundamentales40F41 y, finalmente, iii) impedir que la acci\u00f3n de tutela se convierta en una instancia o recurso adicional para controvertir las decisiones de los jueces41F42\u201d42F43. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el mismo sentido, la Corte reitera la postura unificada en la Sentencia SU-753 de 2019. Seg\u00fan esta, la relevancia constitucional de la acci\u00f3n de tutela contra providencias judiciales implica la verificaci\u00f3n de -al menos tres- elementos43F44. Por una parte, que la controversia exponga una cuesti\u00f3n constitucional y no un debate meramente legal o de contenido econ\u00f3mico44F45. En segundo lugar, que el debate planteado involucre el contenido, alcance y goce de un derecho fundamental45F46. Finalmente, que no se trate del agotamiento de una instancia adicional al proceso ordinario. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Corte ha decidido acciones de tutela contra providencias judiciales y ha determinado que el requisito gen\u00e9rico de la relevancia constitucional es imprescindible para habilitar el estudio material de los defectos espec\u00edficos establecidos por la jurisprudencia. Con base en los elementos descritos, este tribunal ha declarado la improcedencia de recursos de amparo que no satisficieron este presupuesto (tabla 1). \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Tabla 1. Recursos de amparo declarados improcedentes por no satisfacer el requisito de relevancia constitucional \u00a0\u00a0<\/p>\n<p>Sentencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Caso \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Subreglas de decisi\u00f3n \u00a0\u00a0<\/p>\n<p>T-131 de 2021 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>La Corte estudi\u00f3 la acci\u00f3n de tutela promovida por el apoderado de Reficar SAS contra el laudo arbitral del 31 de octubre de 2019, proferido por el Tribunal de Arbitramento de la C\u00e1mara de Comercio de Bogot\u00e1. Dicho laudo conden\u00f3 a Reficar SAS a pagarle al Consorcio ICG-ICSAS, la liquidaci\u00f3n del contrato de consultor\u00eda por valor de $13.286.901.585 y $13.286.901.585, por concepto de intereses moratorios, entre otros. La entidad invoc\u00f3 los defectos sustantivo y f\u00e1ctico.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. La controversia era estrictamente econ\u00f3mica. \u00a0 \u00a0 \u00a0<\/p>\n<p>2. Los cuestionamientos al laudo arbitral estaban dirigidos a discutir aspectos legales. \u00a0 \u00a0 \u00a0<\/p>\n<p>3. Emple\u00f3 la tutela como una nueva instancia judicial para reabrir el proceso arbitral46F47. \u00a0\u00a0<\/p>\n<p>SU-573 de 2019 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>La Corte acumul\u00f3 tres procesos en los que se controvert\u00edan sentencias dictadas por la Subsecci\u00f3n B de la Secci\u00f3n Segunda del Consejo de Estado, por medio de las cuales se neg\u00f3 el reconocimiento y pago de la sanci\u00f3n moratoria por la no consignaci\u00f3n oportuna de las cesant\u00edas prevista por el numeral 3\u00ba del art\u00edculo 99 de la Ley 50 de 1990 y la Ley 344 de 1996, reglamentada por el Decreto 1582 de 1998. Los accionantes consideraban que las decisiones impugnadas vulneraron los derechos fundamentales a la seguridad social, igualdad, seguridad jur\u00eddica y debido proceso. En criterio de los demandantes, las providencias judiciales cuestionadas incurrieron en los defectos sustantivo y desconocimiento del precedente.\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. La controversia era estrictamente econ\u00f3mica. \u00a0 \u00a0 \u00a0<\/p>\n<p>2. Los cuestionamientos estaban dirigidos a discutir aspectos legales. \u00a0 \u00a0 \u00a0<\/p>\n<p>3. La discusi\u00f3n planteada por los actores no implicaba la afectaci\u00f3n de un derecho fundamental. Esto por cuanto los argumentos no se encaminaban a definir el alcance, contenido y goce de garant\u00edas iusfundamentales. \u00a0 \u00a0 \u00a0<\/p>\n<p>4. Emple\u00f3 la tutela como una nueva instancia judicial para reabrir el proceso de nulidad y restablecimiento del derecho. \u00a0\u00a0<\/p>\n<p>T-555 de 2019 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>La Corte estudi\u00f3 la acci\u00f3n de tutela promovida por una ciudadana contra una sentencia de la Subsecci\u00f3n B de la Secci\u00f3n Segunda del Consejo de Estado, por medio de la cual se neg\u00f3 el reconocimiento y pago de la sanci\u00f3n moratoria de las cesant\u00edas entre los a\u00f1os 1999 y 2003. La autoridad judicial neg\u00f3 las pretensiones por cuanto no cumpli\u00f3 los requisitos de la Ley 344 de 1996 y del Decreto 1582 de 1998. La accionante aleg\u00f3 la configuraci\u00f3n de los defectos sustantivo, violaci\u00f3n directa de la Constituci\u00f3n y desconocimiento del precedente. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. La controversia era estrictamente econ\u00f3mica. \u00a0 \u00a0 \u00a0<\/p>\n<p>2. Emple\u00f3 la tutela como una nueva instancia judicial para reabrir el proceso definido por el Consejo de Estado. \u00a0\u00a0<\/p>\n<p>La Corte estudi\u00f3 la acci\u00f3n de tutela dirigida contra las sentencias proferidas en el marco de una acci\u00f3n popular. Los actores consideraban que las decisiones impugnadas incurrieron en los defectos f\u00e1ctico, procedimental absoluto y desconocimiento del precedente. Lo anterior, por cuanto no les fue reconocido el incentivo econ\u00f3mico de la Ley 472 de 1998. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. La controversia era estrictamente econ\u00f3mica. \u00a0 \u00a0 \u00a0<\/p>\n<p>2. Los cuestionamientos estaban dirigidos a discutir aspectos legales. \u00a0\u00a0<\/p>\n<p>T-136 de 2015 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>La Corte estudi\u00f3 la acci\u00f3n de tutela formulada por la Superintendencia de Industria y Comercio contra la Superintendencia de Sociedades (Delegatura para Procedimientos de Insolvencia), a prop\u00f3sito de las decisiones adoptadas dentro de la liquidaci\u00f3n judicial de los bienes de la sociedad Ponce Le\u00f3n Asociados S. A. Ingenieros Consultores. La Superintendencia accionante solicit\u00f3 la protecci\u00f3n de los derechos al debido proceso y acceso a la administraci\u00f3n de justicia, vulnerados con la calificaci\u00f3n del cr\u00e9dito que hizo la superintendencia accionada. La parte actora invoc\u00f3 un defecto sustantivo.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. La controversia era estrictamente econ\u00f3mica. \u00a0 \u00a0 \u00a0<\/p>\n<p>2. Los cuestionamientos estaban dirigidos a discutir aspectos legales. \u00a0\u00a0<\/p>\n<p>T-430 de 2012 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>La Corte estudi\u00f3 la acci\u00f3n de tutela dirigida contra la sentencia proferida en el marco de una acci\u00f3n popular. El actor consider\u00f3 que la revocatoria del reconocimiento del incentivo econ\u00f3mico, vulner\u00f3 los derechos fundamentales al debido proceso e igualdad.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. La controversia era estrictamente econ\u00f3mica. \u00a0 \u00a0 \u00a0<\/p>\n<p>2. Los cuestionamientos estaban dirigidos a discutir aspectos legales. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Con base en lo anterior, la Corte establece que, a efecto de valorar si se cumple el requisito de la relevancia constitucional, es necesario evaluar tanto la pretensi\u00f3n del amparo y los argumentos sobre los cuales se sustenta como -al menos de manera preliminar- la decisi\u00f3n judicial que se cuestiona. Esto con el objetivo de determinar si el problema jur\u00eddico puesto a consideraci\u00f3n del juez de tutela gravita dentro de la \u00f3rbita de los derechos fundamentales o si, por el contrario, la discusi\u00f3n planteada recae sobre asuntos eminentemente patrimoniales, legales o propios del juez ordinario. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el presente caso, este tribunal toma nota de las pretensiones formuladas por el se\u00f1or N\u00e9stor Alfonso Guti\u00e9rrez Romero. Por una parte, la acci\u00f3n de tutela invoc\u00f3 la protecci\u00f3n de los derechos a la igualdad y al debido proceso. En segundo lugar, seg\u00fan el accionante, la sentencia del 13 de febrero de 2020, proferida por la Subsecci\u00f3n B de la Secci\u00f3n Tercera del Consejo de Estado, incurri\u00f3 en los defectos f\u00e1ctico, violaci\u00f3n directa de la Constituci\u00f3n y desconocimiento del precedente. Finalmente, solicit\u00f3 que el juez constitucional act\u00fae \u201cinvalidando la sentencia de la Subsecci\u00f3n A. Con todo respeto, pido que resuelva directamente de fondo, pues la Subsecci\u00f3n A qued\u00f3 impedida para hacerlo, por su manifiesta animadversi\u00f3n y sesgo contra el suscrito\u201d47F48. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De acuerdo con el escrito de tutela, el actor advirti\u00f3 que: i) el abogado Camilo Arciniegas Andrade le cedi\u00f3 el contrato estatal 099 de 1996. ii) El documento de la cesi\u00f3n fue suscrito por el cedente, el cesionario y la entidad p\u00fablica contratante. iii) Sin embargo, la hoja correspondiente a las firmas y a otras cl\u00e1usulas contractuales, por error, qued\u00f3 con la p\u00e1gina correspondiente al contrato 407 de 1994 -que tambi\u00e9n fue cedido por el abogado Arciniegas Andrade al actor-. iv) Para el accionante tal circunstancia no afect\u00f3 la validez de la cesi\u00f3n. v) Seg\u00fan el demandante, existen elementos probatorios que dan cuenta de que la verdadera intenci\u00f3n de la entidad y los contratistas cedentes y cesionario era aceptar la cesi\u00f3n del contrato 099 de 1996 y no del contrato 407 de 1994. vi) Por lo anterior, considera que tiene derecho al reconocimiento y pago de la cuota de \u00e9xito establecida en la cl\u00e1usula tercera del contrato 099 de 1996. vii) En consecuencia, acudi\u00f3 a la acci\u00f3n de controversias contractuales con el fin de obtener el reconocimiento de la cesi\u00f3n del contrato estatal y el pago de la prima de \u00e9xito, equivalente al 10% del valor de las pretensiones solicitadas en contra de Inravisi\u00f3n en sede de nulidad y restablecimiento del derecho, de las que fue absuelta la entidad en sentencia definitiva. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Corte revis\u00f3 el proceso de controversias contractuales y, en concreto, la sentencia del 13 de febrero de 2018, proferida por el Tribunal Administrativo de Cundinamarca. De dicha providencia se destaca lo siguiente. En primer lugar, el ad quem estableci\u00f3 que la cesi\u00f3n de contratos estatales es un acto solemne que requiere de la aceptaci\u00f3n previa, expresa y escrita por parte de la entidad contratante. Por otra parte, en el caso sub examine el documento contentivo de la cesi\u00f3n no corresponde al contrato 099 de 1996, puesto que -tal como lo advirti\u00f3 el actor- la p\u00e1gina de firmas corresponde a la cesi\u00f3n del contrato 407 de 1994. Finalmente, pese a que el actor alleg\u00f3 otros medios de prueba encaminados a demostrar que exist\u00eda la intenci\u00f3n de ceder el contrato, dichos elementos probatorios no supl\u00edan las exigencias legales y jurisprudenciales. Todav\u00eda m\u00e1s cuando el contrato 099 de 1996 ten\u00eda una cl\u00e1usula que prohib\u00eda la cesi\u00f3n sin la autorizaci\u00f3n expresa de la entidad. Dicho de otro modo, para el juez ordinario de segunda instancia, en el proceso no se acredit\u00f3 la existencia del negocio jur\u00eddico de la cesi\u00f3n del contrato estatal, por lo que no hab\u00eda lugar a ordenar el pago de la prima de \u00e9xito.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Este tribunal observa que los cuestionamientos que present\u00f3 el actor en la acci\u00f3n de tutela no se encaminan a obtener la protecci\u00f3n de derechos fundamentales, sino que evidencian \u00fanicamente la inconformidad con la decisi\u00f3n acusada que no accedi\u00f3 a sus pretensiones econ\u00f3micas. Esto por cuanto: i) el defecto f\u00e1ctico endilgado a la sentencia se sustenta en que el juez debi\u00f3 otorgarle mayor valor probatorio a la primera p\u00e1gina del contrato, en lugar de la segunda, es decir, pretend\u00eda que se valorara de manera parcial un documento. Asimismo, el demandante quiso suplir la ausencia del cumplimiento de las formalidades de ley con: a) el testimonio del cedente, b) el poder que le otorg\u00f3 la entidad para que representara sus intereses en el mismo proceso promovido por Antecol, los informes que \u00e9l rindi\u00f3 durante el tiempo que actu\u00f3 como apoderado de la entidad (Inravisi\u00f3n) y el memorial que radic\u00f3 ante el Consejo de Estado en ejercicio de dicho mandato; y c) la p\u00f3liza de cumplimiento que le otorg\u00f3 una empresa aseguradora. Sin embargo, dichas cuestiones fueron analizadas por el juez ordinario. Pero, a\u00fan as\u00ed, este adopt\u00f3 una decisi\u00f3n contraria a los intereses del peticionario. Lo cual, prima facie, no comprometi\u00f3 el alcance, contenido y goce de los derechos invocados. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el desconocimiento del precedente de las Sentencias T-475 de 1992 de la Corte Constitucional y del 18 de febrero de 2010 del Consejo de Estado, el actor argument\u00f3 que las entidades deben actuar de buena fe y corregir los defectos formales que existan en sus actuaciones. En otras palabras, para el actor la ausencia de las formalidades de la cesi\u00f3n del contrato estatal se deb\u00eda subsanar al momento del cobro de la cuota de \u00e9xito, con base en la conducta de las partes. Lo anterior fue razonablemente valorado y decidido por el juez ordinario. En ese orden, para la Corte, ello no trasciende una cuesti\u00f3n que involucre la satisfacci\u00f3n de derechos fundamentales. No se trata de casos an\u00e1logos sino de referencias jurisprudenciales generales sobre la buena fe y las actuaciones de las entidades p\u00fablicas. Esto evidencia que la discusi\u00f3n planteada por el accionante no encierra un debate sobre la aplicaci\u00f3n del principio de igualdad frente al ejercicio jurisdiccional, sino la mera inconformidad con la decisi\u00f3n adoptada por el tribunal accionado. En efecto, aqu\u00ed no se evidencia una actuaci\u00f3n ladina del Estado \u2013lejos est\u00e1 eso y de ah\u00ed la impertinencia de querer hacer an\u00e1logos el caso sub judice y aquel\u2014sino una decisi\u00f3n claramente argumentada sobre la improcedencia de los pagos, todo lo cual fue corroborado en las decisiones aqu\u00ed rese\u00f1adas (tanto en las instancias como en el tr\u00e1mite de tutela).\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Sala Octava encuentra que la presente acci\u00f3n de tutela no cumple el requisito de la relevancia constitucional. Esto por cuanto los argumentos expuestos por el actor, m\u00e1s all\u00e1 de exponer una cuesti\u00f3n iusfundamental, evidencian una discusi\u00f3n de orden legal y ante todo de evidente y claro \u00a0contenido econ\u00f3mico. Asimismo, no est\u00e1 de por medio la definici\u00f3n del alcance, contenido y goce de un derecho fundamental. Por el contrario, la petici\u00f3n de amparo demuestra la inconformidad del actor con la negativa a sus pretensiones econ\u00f3micas por parte del Tribunal Administrativo de Cundinamarca. Es decir, con el recurso de amparo el accionante pretende agotar una instancia judicial adicional al proceso de controversias contractuales. Esto porque -en \u00faltimas- la controversia suscitada se circunscribe a establecer si las formalidades de una cesi\u00f3n contractual estatal se convalidan con la conducta de las partes, aspecto que le corresponde determinar al juez natural. La Sala sustentar\u00e1 las razones que fundamentan la improcedencia de la acci\u00f3n de tutela por ausencia de relevancia constitucional. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El asunto bajo estudio plantea una discusi\u00f3n legal que persigue la satisfacci\u00f3n de una pretensi\u00f3n de \u00edndole econ\u00f3mico48F49. La Corte ha sostenido que le est\u00e1 proscrito \u201cal juez de tutela inmiscuirse de forma imprudente en asuntos de car\u00e1cter netamente legal o reglamentario49F50, so pena de \u2018involucrarse en [cuestiones] que corresponde definir a otras jurisdicciones\u2019\u201d50F51. En este sentido, para este tribunal un asunto carece de relevancia constitucional, cuando, en primer lugar, la discusi\u00f3n est\u00e1 dirigida a aspectos legales de un derecho, en cuanto a la interpretaci\u00f3n que se deber\u00eda hacer de una norma de rango legal o reglamentario, excepto si de esta se deriva la afectaci\u00f3n de una garant\u00eda superior51F52. En segundo lugar, cuando sea evidente la naturaleza econ\u00f3mica de la pretensi\u00f3n52F53. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Al respecto, la Sala Octava de Revisi\u00f3n encuentra oportuno referirse al precedente establecido en la Sentencia T-136 de 2015. Esta decidi\u00f3 una acci\u00f3n de tutela formulada por la Superintendencia de Industria y Comercio contra la Superintendencia de Sociedades (Delegatura para Procedimientos de Insolvencia) a prop\u00f3sito de las decisiones adoptadas dentro de la liquidaci\u00f3n judicial de los bienes de la sociedad Ponce Le\u00f3n Asociados S. A. Ingenieros Consultores. La parte actora solicit\u00f3 la protecci\u00f3n de los derechos al debido proceso y acceso a la administraci\u00f3n de justicia. Estos fueron vulnerados con la calificaci\u00f3n del cr\u00e9dito que hizo la superintendencia accionada. En relaci\u00f3n con el cumplimiento del requisito de la relevancia constitucional, la Corte explic\u00f3: \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cDe lo dicho se deriva que el asunto que se debate en esta ocasi\u00f3n no se encuentra comprendido dentro de los aquellos que la jurisprudencia constitucional ha identificado como de clara relevancia constitucional, puesto que la tutela la interpuso una entidad p\u00fablica contra otra para buscar que se respetara el rango que, a su juicio, debe otorgarse a un cr\u00e9dito a su favor en el marco de un proceso liquidatario, sin que se explique de qu\u00e9 manera dicha situaci\u00f3n pueda dar lugar a una afectaci\u00f3n de derechos o valores consagrados en la Constituci\u00f3n. Todo lo contrario, en el caso planteado se tiene que el asunto que se discute tiene un marcado car\u00e1cter patrimonial, pues lo que est\u00e1 discusi\u00f3n es el pago de un derecho de cr\u00e9dito que se deriva a la imposici\u00f3n de una sanci\u00f3n pecuniaria por parte de la Superintendencia de Industria y Comercio a la sociedad comercial Ponce Le\u00f3n S. A. Ingenieros Consultores-en liquidaci\u00f3n, lo que excluir\u00eda de plano la relevancia constitucional del asunto y, por lo tanto, la posibilidad de acudir a la tutela para proteger los derechos que la entidad tutelante considera afectados\u201d53F54. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Sobre el mismo punto, en la Sentencia SU-573 de 2019, la Sala Plena estudi\u00f3 los procesos de tutela acumulados a trav\u00e9s de los cuales se controvert\u00edan sentencias del Consejo de Estado que -en sede de nulidad y restablecimiento del derecho- negaron el pago de la sanci\u00f3n moratoria. En esa oportunidad, la Corte concluy\u00f3: \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cEl presente asunto comporta, de un lado, un debate legal orientado a determinar si la sanci\u00f3n moratoria por la no consignaci\u00f3n de las cesant\u00edas, prevista por el numeral 3\u00ba del art\u00edculo 99 de la Ley 50 de 1990, es aplicable a los docentes nacionales o nacionalizados por virtud de la Ley 344 de 1996, reglamentada por el Decreto 1582 de 1998 -argumento de los accionantes-, o si, por el contrario, \u201ca los educadores del sector p\u00fablico no le es aplicable los art\u00edculos 99, 102, y 104 de la Ley 50 de 1990, que contemplaron el plazo para la liquidaci\u00f3n del valor liquidado anualmente con anterioridad al 15 de febrero y la sanci\u00f3n moratoria para el empleador que incumpla esta obligaci\u00f3n, pues estas normas fueron extendidas por disposici\u00f3n del art\u00edculo 1 del Decreto 1582 de 1998, \u00fanicamente a los servidores p\u00fablicos del nivel territorial y vinculados a partir del 31 de diciembre de 1996 que se afilien a los fondos privados de cesant\u00edas\u201d -argumento del Consejo de Estado-. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De otro lado, la sanci\u00f3n moratoria por no consignaci\u00f3n oportuna de las cesant\u00edas no es un derecho fundamental ni est\u00e1 ligada a la satisfacci\u00f3n de una garant\u00eda de naturaleza constitucional. La jurisprudencia de esta Corporaci\u00f3n ha reconocido el car\u00e1cter irrenunciable de las cesant\u00edas, como una prestaci\u00f3n patronal de rango legal cuya finalidad es \u201cauxiliar a la persona que se queda temporalmente sin trabajo\u201d 54F55. Por tanto, solo en la medida en que lo reclamado sea dicha prestaci\u00f3n, la tutela devendr\u00eda procedente cuando se advierta que su falta de pago conlleva la vulneraci\u00f3n del derecho al m\u00ednimo vital y a la seguridad social del trabajador. En consecuencia, cualquier pago adicional que no corresponda a la finalidad misma de las cesant\u00edas, sino a una penalidad para el empleador que no las consigna al fondo o las paga al trabajador en los t\u00e9rminos solicitados, es un reconocimiento de fuente legal con car\u00e1cter netamente patrimonial, que no amerita la intervenci\u00f3n del juez de tutela. Adem\u00e1s, seg\u00fan se deriva de los antecedentes de los casos acumulados, no es prima facie admisible considerar que la falta de reconocimiento de aquella pretensi\u00f3n econ\u00f3mica pueda comprometer su m\u00ednimo vital, en la medida en que los tres accionantes mantienen vigente su v\u00ednculo laboral con el Departamento del Atl\u00e1ntico \u2013como se refiere, igualmente, en el apartado que sigue\u201d55F56. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La misma subregla de decisi\u00f3n relacionada con la discusi\u00f3n de aspectos de orden legal y exclusivamente patrimonial fue aplicada en la Sentencia T-131 de 2021. En esta se decidi\u00f3 la acci\u00f3n de tutela promovida por Reficar SAS contra la condena impuesta por el Tribunal de Arbitramento de la C\u00e1mara de Comercio de Bogot\u00e1. Al respecto, la Sala S\u00e9ptima de Revisi\u00f3n concluy\u00f3: \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cEn primer lugar, en concordancia con las pretensiones incoadas, la solicitud de amparo no supone, a priori, el desconocimiento del derecho fundamental al debido proceso de Reficar SAS en su faceta constitucional. En efecto, la acci\u00f3n de tutela plantea una controversia estrictamente econ\u00f3mica, consistente en la inconformidad de esa entidad con el laudo arbitral que la conden\u00f3 al pago de intereses por mora, como resultado del incumplimiento del Contrato celebrado con el Consorcio y, espec\u00edficamente, por no concurrir oportunamente a su liquidaci\u00f3n. || En segundo lugar, los presuntos defectos en que incurri\u00f3 el laudo arbitral se orientan i) a resolver aspectos que no trascienden las meras cuestiones legales y ii) a cuestionar el criterio que el Tribunal, dentro de su \u00e1mbito de autonom\u00eda, us\u00f3 para decidir\u201d56F57. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Corte observa que -en el asunto sub examine- el principal reparo del actor a la providencia judicial impugnada recae sobre el valor de las pruebas para demostrar la cesi\u00f3n del contrato estatal. Sin embargo, el aspecto f\u00e1ctico identificado se enfrenta a la interpretaci\u00f3n legal de las reglas que se exigen para la validez de un negocio jur\u00eddico. Dicho de otro modo, el actor discute la aplicaci\u00f3n de las normas sobre contrataci\u00f3n estatal.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En efecto, para el demandante, la irregularidad en la cesi\u00f3n del contrato 099 de 1996 (cuya primera p\u00e1gina corresponde a ese contrato mientras que la segunda -que contiene las firmas- pertenece al contrato 407 de 1994) es un asunto menor que no afect\u00f3 para nada la validez del negocio jur\u00eddico. Para el tribunal, tal circunstancia result\u00f3 determinante para determinar si la mencionada cesi\u00f3n del contrato estatal cumpl\u00eda con las solemnidades exigidas en la Ley 80 de 1993. Entre ellas, la de la aceptaci\u00f3n previa, expresa y escrita de la cesi\u00f3n del contrato por parte de la entidad estatal. Con base en ello, el juez administrativo de segunda instancia concluy\u00f3 que la cesi\u00f3n contractual no cumpl\u00eda con las exigencias legales de manera que neg\u00f3 el reconocimiento y pago de la cuota de \u00e9xito. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Sala encuentra que, si bien el accionante expone que la decisi\u00f3n impugnada comporta la vulneraci\u00f3n de los derechos a la igualdad y al debido proceso, por cuanto -seg\u00fan su opini\u00f3n- la autoridad judicial valor\u00f3 inadecuadamente las pruebas, desconoci\u00f3 el precedente sobre la buena fe y viol\u00f3 los art\u00edculos 13 y 83 de la Carta. Lo cierto es que los argumentos expuestos en el escrito de tutela evidencian que la discusi\u00f3n del actor es de orden legal. Esto por cuanto considera que el incumplimiento de las solemnidades de la cesi\u00f3n del contrato es un asunto menor que se puede suplir con pruebas adicionales (i.e. testimonios, p\u00f3liza de cumplimiento de contrato e informes sobre actuaciones). \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Lo anterior da cuenta de que, en realidad, la presunta vulneraci\u00f3n a los derechos fundamentales del accionante versa sobre una cuesti\u00f3n de interpretaci\u00f3n meramente legal que no impacta la garant\u00eda de los derechos fundamentales sino meramente patrimoniales57F58. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En efecto, la pretensi\u00f3n del actor persigue el pago de la cuota de \u00e9xito prevista en la cl\u00e1usula tercera del contrato 099 de 1996. Sin embargo, la Corte encuentra que el reconocimiento y el pago de esa pretensi\u00f3n no concretan el contenido de un derecho fundamental ni est\u00e1 ligada a la satisfacci\u00f3n de una garant\u00eda de naturaleza constitucional. Para este tribunal, tal pretensi\u00f3n es netamente econ\u00f3mica y no est\u00e1 encaminada a satisfacer el m\u00ednimo vital del peticionario. Esto ocurre porque no se discute el pago de los honorarios sino de una prima adicional, de cuyo cumplimiento no se deriva la satisfacci\u00f3n de ning\u00fan derecho (como aquellos de car\u00e1cter irrenunciable como el salario o prestaciones sociales58F59) ni se busca evitar un perjuicio irremediable. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por lo anterior, la Sala concluye que en el asunto bajo estudio no se acredit\u00f3 el primer elemento. Se pretende discutir una interpretaci\u00f3n legal propia de los jueces ordinarios con el fin de obtener la satisfacci\u00f3n de una pretensi\u00f3n con car\u00e1cter netamente patrimonial. Como ha indicado la Corte en varios casos similares, ese tipo de pretensiones no amerita la intervenci\u00f3n del juez de tutela59F60. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El debate planteado no involucra el contenido, alcance y goce de un derecho fundamental60F61. Con fundamento en la naturaleza de la acci\u00f3n de tutela y los principios de efectividad, inmediatez y subsidiariedad que gobiernan este mecanismo, la Corte ha sostenido que la cuesti\u00f3n debe revestir una clara, marcada e indiscutible relevancia constitucional61F62.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para esta Sala, este presupuesto implica que la causa que origina la acci\u00f3n de tutela sea el desconocimiento de un derecho fundamental, ya sea en la interpretaci\u00f3n62F63, aplicaci\u00f3n, determinaci\u00f3n del contenido o alcance de un derecho fundamental por parte de una autoridad judicial63F64. Lo anterior impone al juez constitucional la obligaci\u00f3n de justificar su intervenci\u00f3n en clave de vulneraci\u00f3n de garant\u00edas iusfundamentales64F65. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El debate planteado en el caso sub judice, si bien invoca la protecci\u00f3n de derechos fundamentales, lo cierto es que no reviste trascendencia constitucional. Como se ha indicado, la inconformidad del actor se restringe al pago de la cuota de \u00e9xito del contrato 099 de 1996. Esta pretensi\u00f3n no representa una amenaza directa o indirecta para la igualdad o el debido proceso invocados en la acci\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Como se explic\u00f3 previamente, la finalidad que persigue el accionante es el reconocimiento y pago del 10% de las pretensiones del caso Antecol; en el que \u00e9l fungi\u00f3 como apoderado de Inravisi\u00f3n y el MinTic. No obstante, la Corte no advierte un problema de orden constitucional que conlleve la afectaci\u00f3n de garant\u00edas superiores. El asunto no se relaciona con el pago de honorarios, salarios o mesadas pensionales, sino con una prestaci\u00f3n accesoria del derecho principal a recibir el pago de los honorarios derivados de la prestaci\u00f3n del servicio. El fundamento de este \u00faltimo es una cesi\u00f3n de un contrato estatal sin el lleno de los requisitos legales. Para esta Corporaci\u00f3n, el debate propuesto no expone una cuesti\u00f3n de naturaleza constitucional, sino legal y patrimonial. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para la Sala Octava de Revisi\u00f3n la controversia es de car\u00e1cter dinerario y, en principio, por tanto no se afecta el m\u00ednimo vital del accionante. Como se advirti\u00f3 l\u00edneas atr\u00e1s, el actor no afirm\u00f3 ni acredit\u00f3 que la ausencia del pago de la cuota de \u00e9xito tuviera graves implicaciones econ\u00f3micas o que dichos recursos fueren imprescindibles para su sostenimiento. En este sentido, en la Sentencia SU-573 de 2019, la Corte lleg\u00f3 a conclusiones similares en el caso de docentes que impugnaron una sentencia ordinaria a trav\u00e9s de la cual reclamaban el pago de la sanci\u00f3n moratoria. \u00a0 \u00a0<\/p>\n<p>1. En esa oportunidad, la Sala Plena concluy\u00f3 que la inconformidad de los actores se restring\u00eda al pago de un derecho patrimonial que no involucraba el derecho a la seguridad social, en tanto no compromet\u00eda salarios o mesadas pensionales ciertas que amenazaran el m\u00ednimo vital de los entonces accionantes. En otras palabras, en la Sentencia SU-573 de 2019, la Corte concluy\u00f3 que la negativa al pago de la sanci\u00f3n moratoria no pon\u00eda en riesgo el m\u00ednimo vital de los actores y, por tanto, carec\u00eda de relevancia constitucional. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Sobre el incumplimiento del requisito de relevancia constitucional por discutir aspectos que no est\u00e1n referidos al alcance, contenido o goce de derechos fundamentales, en la Sentencia T-136 de 2015, la Corte concluy\u00f3: \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cDe lo anterior, la Sala concluye que la disconformidad de la parte pretensionante (sic) tiene como fuente no una cuesti\u00f3n de forma, propio del derecho fundamental al debido proceso, sino un asunto sustancial que tiene que ver con cu\u00e1l es la interpretaci\u00f3n m\u00e1s adecuada que puede darse a la normatividad rese\u00f1ada. Al tomar en cuenta que la fuente de la alegada vulneraci\u00f3n a los derechos fundamentales de la actora devendr\u00eda de una cuesti\u00f3n hermen\u00e9utica y no del desconocimiento de las normas procesales que rigen el tr\u00e1mite de liquidaci\u00f3n judicial de sociedades comerciales ante la Superintendencia, se descarta que la relevancia constitucional del asunto se siga de una potencial afectaci\u00f3n del derecho al debido proceso.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En cuanto a este punto, conviene recordar que no cualquier violaci\u00f3n al debido proceso puede ser impugnada en sede de tutela, pues para que la acci\u00f3n resulte procedente deben estar en juego la garant\u00eda de los derechos fundamentales de una persona. Por lo anterior, conviene recordar que de acuerdo con el inciso 2 del art. 29 Superior \u201cNadie podr\u00e1 ser juzgado sino conforme a leyes preexistentes al acto que se le imputa, ante juez o tribunal competente y con observancia de la plenitud de las formas propias de cada juicio\u201d \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Al estimar que lo que se debate es la manera en que han de interpretarse las disposiciones legales que rigen el procedimiento de liquidaci\u00f3n judicial de sociedades comerciales llevado a cabo por la Superintendencia de Sociedades, se tiene que la controversia de fondo en esta ocasi\u00f3n reviste un car\u00e1cter eminentemente legal, lo que descarta su relevancia constitucional y, por lo tanto, la procedencia de la tutela incoada\u201d65F66. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Sala encuentra que los fundamentos de la petici\u00f3n de amparo evidencian que el caso bajo estudio no involucra el alcance, interpretaci\u00f3n o goce de los derechos a la igualdad y al debido proceso. Pues -se insiste- la discusi\u00f3n planteada gravita sobre la acreditaci\u00f3n de una cesi\u00f3n contractual sin el lleno de las formalidades exigidas por la ley. Este aspecto de ninguna manera expone un trato desigual ni el desconocimiento del debido proceso por parte del Tribunal Administrativo de Cundinamarca al decidir la demanda de controversias contractuales promovida por el accionante. En criterio de la Corte, esta conclusi\u00f3n se basa en dos fundamentos. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En primer lugar, este tribunal precisa que la garant\u00eda de la igualdad frente a las actuaciones judiciales se deriva del mandato de que los jueces deben resolver casos an\u00e1logos con similares argumentos. Esto implica que, si existe un precedente en determinado sentido, en principio, un caso con identidad f\u00e1ctica se resuelva siguiendo esos derroteros; salvo que se expongan buenas razones que justifiquen una sentencia en contrario. Seg\u00fan lo reiter\u00f3 la Corte66F67, la protecci\u00f3n del derecho a la igualdad \u201csolo tiene cabida cuando una decisi\u00f3n ri\u00f1e de manera abierta con la Constituci\u00f3n y es definitivamente incompatible con la jurisprudencia trazada por la Corte Constitucional al definir el alcance y l\u00edmites de los derechos fundamentales\u201d67F68. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Sala revis\u00f3 la acci\u00f3n de tutela y encontr\u00f3 que, si bien el actor invoc\u00f3 el defecto por desconocimiento del precedente -en virtud del cual, se podr\u00eda ver afectado el derecho a la igualdad-, lo cierto es que los argumentos apuntaban al principio de la buena fe. En este caso, sin mencionar siquiera cu\u00e1les reglas de decisi\u00f3n de un caso igual fueron desconocidas. Las apreciaciones sobre el particular fueron m\u00ednimas, generales y ambiguas. Dicho de otra manera, no se est\u00e1 en presencia de \u201cdecisiones contradictorias en casos id\u00e9nticos\u201d68F69 dado que no existe identidad f\u00e1ctica y jur\u00eddica con las Sentencias T-475 de 1992 de la Corte y del 18 de febrero de 2010 del Consejo de Estado. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Lo anterior quiere decir que la Corte no encuentra que la sentencia impugnada hubiere afectado el derecho a la igualdad del se\u00f1or N\u00e9stor Alfonso Guti\u00e9rrez. Por lo contrario, la decisi\u00f3n del 13 de febrero de 2020 se fundament\u00f3 en el precedente aplicable del \u00f3rgano de cierre de la jurisdicci\u00f3n contencioso administrativa; por lo que mal podr\u00eda desconocer el mandato constitucional de igualdad. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En segundo lugar, la vulneraci\u00f3n del debido proceso puede ser impugnada en sede de tutela cuando tiene como objetivo proteger al sujeto procesal que se ha visto afectado por los excesos en el ejercicio de poder del juez ordinario, es decir, cuando se trata de actuaciones arbitrarias, caprichosas e injustificadas69F70. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Corte revis\u00f3 la Sentencia del 13 de febrero de 2020 del Tribunal Administrativo de Cundinamarca. Esta determin\u00f3 que no hab\u00eda lugar al reconocimiento y pago de la cuota de \u00e9xito porque no se acredit\u00f3 que la cesi\u00f3n del contrato hubiere sido previa, expresa y escrita. Tal determinaci\u00f3n se fundament\u00f3 en la Ley 80 de 1993 y en la jurisprudencia del Consejo de Estado sobre la materia. La Secci\u00f3n Tercera tuvo en cuenta las pruebas que el actor aport\u00f3 para acreditar la cesi\u00f3n del contrato estatal, sin embargo, no le otorg\u00f3 el valor probatorio que el accionante pretend\u00eda, por cuanto ninguna de ellas supl\u00eda la exigencia legal. Esto quiere decir que el juez ordinario sustent\u00f3 su decisi\u00f3n de manera razonable y con base en las normas aplicables y las pruebas aportadas. De manera que, mal podr\u00eda concluirse que desconoci\u00f3 el debido proceso del actor. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En suma, esta Corporaci\u00f3n concluye que la presente acci\u00f3n no discute el contenido, alcance, aplicaci\u00f3n o goce de un derecho fundamental, sino la satisfacci\u00f3n de una pretensi\u00f3n econ\u00f3mica derivada de una cl\u00e1usula contractual. Por lo anterior, no se cumple el segundo elemento de la relevancia constitucional70F71. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La acci\u00f3n de tutela pretende agotar una instancia adicional al proceso ordinario de controversias contractuales71F72. La Corte ha establecido que \u201cla tutela contra providencias judiciales no da lugar a una tercera instancia, ni puede reemplazar los recursos ordinarios\u201d72F73. Esto se justifica en el hecho de que la competencia del juez de tutela se restringe a asuntos de relevancia constitucional y con el prop\u00f3sito de salvaguardar los derechos fundamentales. Tal premisa implica que la autoridad judicial valore si la cuesti\u00f3n planteada gira en torno a derechos fundamentales o si, por el contrario, encierra un debate legal como si se tratara de una instancia adicional. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En la Sentencia T-131 de 2021, la Sala S\u00e9ptima de Revisi\u00f3n, al decidir la acci\u00f3n de tutela promovida por Reficar SAS contra el Tribunal de Arbitramento de la C\u00e1mara de Comercio, respecto de la ausencia de relevancia constitucional explic\u00f3: \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cLa Sala observa que, en el fondo, mediante la exposici\u00f3n de los dos aspectos indicados, se busca debatir un asunto que ya fue juzgado por el Tribunal y frente al cual las partes tuvieron la oportunidad, en esa instancia, de presentar sus argumentos y alegaciones. Desde esta perspectiva, este es un motivo m\u00e1s para concluir que la acci\u00f3n de tutela es empleada como una nueva instancia judicial para reabrir el proceso arbitral. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De este modo, se concluye que la acci\u00f3n de tutela interpuesta por Reficar SAS contra el laudo arbitral aprobado el 31 de octubre de 2019 no satisface el requisito general de relevancia constitucional, porque i) no supone, a priori, el desconocimiento del derecho fundamental al debido proceso de Reficar SAS en su faceta constitucional, en la medida en que aquella plantea una controversia estrictamente econ\u00f3mica; ii) los presuntos defectos en que incurri\u00f3 el laudo arbitral se orientan a resolver aspectos que no trascienden las meras cuestiones legales y a cuestionar el criterio que el Tribunal, dentro de su \u00e1mbito de autonom\u00eda, us\u00f3 para decidir; iii) la tutela es empleada como una nueva instancia judicial para reabrir el proceso arbitral; y iv) esta no re\u00fane las condiciones necesarias para aplicar el precedente fijado en la Sentencia SU-081 de 2020, en relaci\u00f3n con la protecci\u00f3n del patrimonio p\u00fablico\u201d73F74. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En la Sentencia SU-573 de 2019, este tribunal concluy\u00f3 que la acci\u00f3n formulada por los docentes oficiales con el fin de obtener el pago de la sanci\u00f3n moratoria pretend\u00eda agotar una instancia adicional del proceso de nulidad y restablecimiento del derecho que hab\u00eda decidido sus pretensiones en forma negativa. En ese sentido, la Sala Plena concluy\u00f3: \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cEn el presente caso, la tutela es empleada con el prop\u00f3sito de reabrir una discusi\u00f3n que ya fue resuelta por el Consejo de Estado. Esto es evidente si se tiene en cuenta que, tras obtener una respuesta desfavorable a sus intereses, los accionantes acuden a la tutela, bajo la supuesta configuraci\u00f3n de dos defectos espec\u00edficos, con el fin de que el juez constitucional acceda a las mismas pretensiones incoadas en el proceso de nulidad y restablecimiento del derecho. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En atenci\u00f3n a lo expuesto, y de acuerdo a las particulares circunstancias del asunto sub examine, la Sala concluye que no le corresponde reabrir el debate sobre un asunto meramente legal, a efectos de realizar el an\u00e1lisis de correcci\u00f3n de la sentencia74F75 y, en consecuencia, identificar cu\u00e1l es la interpretaci\u00f3n que los jueces de la jurisdicci\u00f3n contencioso administrativo deben acoger acerca del alcance del art\u00edculo 99 de la Ley 50 de 1990 y de la Ley 344 de 1996, reglamentada por el Decreto 1582 de 1998, en cuanto al reconocimiento de una penalidad por no consignaci\u00f3n oportuna de las cesant\u00edas en el r\u00e9gimen docente. Dicha labor de interpretaci\u00f3n y unificaci\u00f3n de la jurisprudencia le corresponde al m\u00e1ximo tribunal de lo contencioso administrativo, \u00f3rgano de cierre de dicha jurisdicci\u00f3n, al cual le corresponde \u201cunificar la jurisprudencia en el \u00e1mbito de su jurisdicci\u00f3n\u201d75F76. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el presente caso, la tutela es empleada con el prop\u00f3sito de reabrir un debate procesal que ya fue resuelto por el Tribunal Administrativo de Cundinamarca. Esto es evidente si se tiene en cuenta que, tras obtener una respuesta desfavorable a sus intereses, el accionante acudi\u00f3 al recurso de amparo con el fin de que el juez constitucional accediera a las mismas pretensiones incoadas en el proceso de controversias contractuales. Incluso la petici\u00f3n de la tutela es que se profiera una sentencia sustitutiva que, en \u00faltimas, persigue que se ordene el pago de la cuota de \u00e9xito solicitada. Es decir, el objetivo de la acci\u00f3n constitucional es obtener un provecho econ\u00f3mico. De manera que se trata de una pretensi\u00f3n propia de un tr\u00e1mite ordinario. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para la Corte es evidente que las cuestiones planteadas por el actor en clave de defectos f\u00e1ctico, por violaci\u00f3n directa de la Constituci\u00f3n y desconocimiento del precedente, en el fondo, persiguen el agotamiento de una instancia judicial adicional. En efecto, el actor propone una discusi\u00f3n sobre los elementos que acreditan la cesi\u00f3n de un contrato estatal como si estuviera agenciando sus intereses ante el juez ordinario. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por las razones expuestas, la Sala Octava concluye que el asunto bajo estudio no satisface el requisito de la relevancia constitucional. De manera que la acci\u00f3n formulada es improcedente al no cumplir uno de los requisitos generales de procedencia. En consecuencia, no hay lugar a estudiar los defectos endilgados a la sentencia proferida por la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En esas condiciones, la Corte revocar\u00e1 los fallos del 24 de septiembre y 24 de noviembre de 2020, proferidos por las Subsecciones A y B de la Secci\u00f3n Tercera del Consejo de Estado, en primera y segunda instancia, respectivamente, por medio de los cuales se neg\u00f3 la acci\u00f3n de tutela promovida por N\u00e9stor Alfonso Guti\u00e9rrez Romero contra la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca. En su lugar, se declarar\u00e1 improcedente la petici\u00f3n de amparo de la referencia. \u00a0 \u00a0<\/p>\n<p>VI. DECISI\u00d3N \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Octava de Revisi\u00f3n de la Corte Constitucional, administrando justicia en nombre del pueblo y por mandato de la Constituci\u00f3n Pol\u00edtica, \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Primero. REVOCAR los fallos del 24 de septiembre y 24 de noviembre de 2020, proferidos por las Subsecciones A y B de la Secci\u00f3n Tercera del Consejo de Estado, en primera y segunda instancia, respectivamente, por medio de los cuales se neg\u00f3 la acci\u00f3n de tutela promovida por N\u00e9stor Alfonso Guti\u00e9rrez Romero contra la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca. En su lugar, DECLARAR IMPROCEDENTE la petici\u00f3n de amparo de la referencia, conforme a lo expuesto en esta decisi\u00f3n.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Segundo. L\u00cdBRENSE por Secretar\u00eda General las comunicaciones de que trata el art\u00edculo 36 del Decreto 2591 de 1991. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese, publ\u00edquese y c\u00famplase. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>JOS\u00c9 FERNANDO REYES CUARTAS \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ALBERTO ROJAS R\u00cdOS \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DIANA FAJARDO RIVERA \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>Salvamento de voto \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0<\/p>\n<p>Secretaria General \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DIANA FAJARDO RIVERA\u00a0 \u00a0<\/p>\n<p>A LA SENTENCIA T-267\/2177 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Se otorga un alcance errado al requisito de relevancia constitucional, en materia de tutela contra providencias judiciales (Salvamento de voto) \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>CONTRATACION ESTATAL-Principios que la rigen (Salvamento de voto) \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(\u2026) el an\u00e1lisis de fondo de la solicitud le habr\u00eda permitido a la Corte reiterar la jurisprudencia sobre los principios constitucionales de la contrataci\u00f3n estatal y evaluar si el postulado de \u201cno se escucha a quien alega su propia falta\u201d aplicado por el Tribunal Administrativo de Cundinamarca con fundamento en un pronunciamiento de esta Corporaci\u00f3n resultaba excesivamente r\u00edgido de cara al planteamiento del demandante o si, por el contrario, el mismo se advert\u00eda adecuado para proteger los principios constitucionales de prevalencia del inter\u00e9s general o defensa del patrimonio p\u00fablico. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Referencia: T-8.121.591 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Acci\u00f3n de tutela instaurada por N\u00e9stor Alfonso Guti\u00e9rrez Romero contra la Subsecci\u00f3n A de la Secci\u00f3n Tercera del Tribunal Administrativo de Cundinamarca \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Magistrado ponente: \u00a0<\/p>\n<p>Jos\u00e9 Fernando Reyes Cuartas \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1. Con el respeto acostumbrado por las decisiones adoptadas por la Sala Octava de Revisi\u00f3n, a continuaci\u00f3n, presento las razones que me apartan de la posici\u00f3n mayoritaria. En mi criterio, la Corte Constitucional debi\u00f3 proferir un pronunciamiento de fondo, pues la solicitud satisfizo los requisitos generales de procedibilidad de la acci\u00f3n de tutela contra providencias judiciales. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2. La Sentencia T-267 de 2021 determin\u00f3 que la acci\u00f3n de tutela cumpli\u00f3 la mayor parte de estos presupuestos, salvo el de relevancia constitucional. En particular, se refiri\u00f3 a este \u00faltimo y se\u00f1al\u00f3 que conforme a la Sentencia SU-573 de 201978 se deben acreditar tres elementos para verificar su satisfacci\u00f3n: (i) que la controversia exponga una cuesti\u00f3n constitucional y no un debate meramente legal o de naturaleza econ\u00f3mica; (ii) que la problem\u00e1tica planteada involucre el contenido, alcance y goce de un derecho fundamental; y (iii) que la acusaci\u00f3n no suponga el agotamiento de una instancia adicional al proceso ordinario. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>3. Al aplicar estas reglas al caso concreto la Sentencia T-267 de 2021 encontr\u00f3 que el requisito de relevancia constitucional no se satisfac\u00eda por cuanto los se\u00f1alamientos del demandante se dirig\u00edan a cuestionar el alcance de normas legales sobre contrataci\u00f3n estatal; el asunto comprend\u00eda el pago de una prima de \u00e9xito de un contrato de prestaci\u00f3n de servicios y, por lo tanto, se trataba de una controversia dineraria que no involucraba la afectaci\u00f3n del m\u00ednimo vital; el prop\u00f3sito del solicitante era reabrir un debate procesal resuelto por el juez ordinario; y, finalmente, advirti\u00f3 que la sentencia atacada se adopt\u00f3 a partir de un an\u00e1lisis razonable de las normas aplicables al caso y las pruebas aportadas al tr\u00e1mite, por lo que se descartaba la violaci\u00f3n de los derechos fundamentales al debido proceso y a la igualdad.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>4. Bajo tal marco, no comparto la postura de la mayor\u00eda por las razones que siguen. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>5. En primer lugar, considero que el empleo de las pautas consagradas en la Sentencia SU-573 de 2019 para analizar el presupuesto de relevancia constitucional no proced\u00eda en el presente asunto. La mayor\u00eda debi\u00f3 tener en cuenta que en esa ocasi\u00f3n la acci\u00f3n de tutela se dirigi\u00f3 contra un fallo del Consejo de Estado y, por lo tanto, el mayor rigor aplicado en esa oportunidad al analizar el requisito de relevancia constitucional se explica a partir del car\u00e1cter restringido de la acci\u00f3n de tutela contra providencias de una Alta Corte.79 Sin embargo, en el presente asunto la solicitud de amparo se propuso contra una decisi\u00f3n del Tribunal Administrativo de Cundinamarca y, en ese sentido, el mencionado precedente de Sala Plena no pod\u00eda ser trasladado mec\u00e1nicamente para analizar la relevancia constitucional de este caso. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>6. As\u00ed mismo, a mi juicio la proposici\u00f3n de argumentos de \u00edndole legal o probatoria no descarta por s\u00ed solo el cumplimiento del presupuesto de relevancia constitucional, pues resulta razonable y apenas entendible que para estructurar el cargo se acuda a alegaciones de este tipo por cuanto es necesario acreditar la forma en que se transgredi\u00f3 el debido proceso u otro derecho fundamental. De esta manera, aunque pueda parecer un debate de solo legalidad, lo cierto es que cuando la aplicaci\u00f3n errada de una norma o la no aplicaci\u00f3n de aquella que rige el asunto determinan el acceso a la pretensi\u00f3n ordinaria que persigue el actor, sin duda se presenta un problema de \u00edndole constitucional significativo de una indebida administraci\u00f3n de justicia. Lo mismo sucede cuando se deja de valorar una prueba relevante para el caso o se valora arbitrariamente. En estos eventos procede la intervenci\u00f3n del juez constitucional. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7. Igualmente, como lo manifest\u00e9 en los salvamentos de voto a las sentencias T-248 de 201880, T-555 de 201981 y SU-573 de 2019,82 en mi criterio el an\u00e1lisis del requisito de relevancia constitucional no puede acarrear un juicio sobre el fondo de la cuesti\u00f3n sometida a conocimiento del juez de tutela. La sentencia de la que me aparto incumpli\u00f3 esta premisa, pues al examinar este presupuesto sostuvo que el Tribunal Administrativo de Cundinamarca no vulner\u00f3 el derecho a la igualdad y al debido proceso del solicitante.83 Un pronunciamiento en ese sentido es significativo de un prejuzgamiento indebido y desconoce que la conclusi\u00f3n sobre la existencia o no de una transgresi\u00f3n a un derecho fundamental es un aspecto de fondo que solo puede darse luego de analizar si la providencia acusada incurri\u00f3 en alguno de los defectos constitucionales identificados en la jurisprudencia de esta Corporaci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>8. Bajo tal perspectiva, considero que en el presente caso la solicitud de tutela en principio ten\u00eda un alcance constitucional, pues estaba de por medio un reclamo por transgresi\u00f3n del derecho al debido proceso (Art. 29 de la CP), el principio constitucional de buena fe (Art. 83 de la CP) y la prevalencia del derecho sustancial (Art. 228 de la CP). As\u00ed mismo, el an\u00e1lisis de fondo de la solicitud le habr\u00eda permitido a la Corte reiterar la jurisprudencia sobre los principios constitucionales de la contrataci\u00f3n estatal y evaluar si el postulado de \u201cno se escucha a quien alega su propia falta\u201d aplicado por el Tribunal Administrativo de Cundinamarca con fundamento en un pronunciamiento de esta Corporaci\u00f3n84 resultaba excesivamente r\u00edgido de cara al planteamiento del demandante o si, por el contrario, el mismo se advert\u00eda adecuado para proteger los principios constitucionales de prevalencia del inter\u00e9s general o defensa del patrimonio p\u00fablico.85 De este modo, la Sentencia T-267 de 2021 no solo se pronunci\u00f3 sobre el fondo del asunto en una etapa preliminar, sino que lo hizo adem\u00e1s sin considerar la jurisprudencia constitucional aplicable en estos casos. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>9. El requisito de relevancia constitucional cumple una funci\u00f3n importante para racionalizar el empleo de la acci\u00f3n de tutela contra providencias judiciales y para impedir intervenciones desproporcionadas a los principios de autonom\u00eda e independencia judicial. Por tal raz\u00f3n, en los eventos en que se constate que la pretensi\u00f3n de tutela no plantea un verdadero cuestionamiento ius fundamental, lo pertinente es declarar improcedente la acci\u00f3n dado que \u201cel juez constitucional no puede entrar a estudiar cuestiones que no tienen una clara y marcada importancia constitucional so pena de involucrarse en asuntos que corresponde definir a otras jurisdicciones.\u201d86 En el presente caso, sin embargo, la trascendencia constitucional del asunto fue acreditada por el accionante y, por tal motivo, me separo de la postura mayoritaria que consider\u00f3 lo contrario. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>10. Por estas razones, salvo el voto en la presente oportunidad. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Fecha ut supra,\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DIANA FAJARDO RIVERA \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 Escrito de tutela, p. 5. \u00a0<\/p>\n<p>2 Para el accionante la inconsistencia evidenciada por el MinTic: \u201cSe trataba, desde luego, de un intrascendente error de digitaci\u00f3n: era claro que las partes hab\u00edan firmado una cesi\u00f3n para cada contrato; y que, al preparar para la firma el documento de cesi\u00f3n del contrato 099, INRAVISI\u00d3N hab\u00eda tomado como plantilla la cesi\u00f3n del contrato 407 y repetido por error la segunda p\u00e1gina este, que as\u00ed fue firmada por las partes; sin embargo, no cab\u00eda duda de que el contrato cedido era el n\u00famero 099, tal como se expresa en la primera p\u00e1gina del documento de cesi\u00f3n y lo corroboran el poder que me confiri\u00f3 INRAVISI\u00d3N, la garant\u00eda de cumplimiento que le otorgu\u00e9 y los informes que rend\u00ed durante m\u00e1s de 12 a\u00f1os. El 16 de marzo de 2015 present\u00e9 la factura por concepto de honorarios. Sin embargo, con oficio del 8 de abril de 2015 el Ministerio la devolvi\u00f3, argumentando que el art\u00edculo 39 de la Ley 80 dispone que el contrato estatal constar\u00e1 por escrito; y que en este caso, no aparec\u00eda firmada la cesi\u00f3n del contrato 099. Dijo el Ministerio: En consecuencia, al revisar y verificar la documentaci\u00f3n que el extinto Instituto Nacional de Radio y Televisi\u00f3n INRAVISI\u00d3N traslad\u00f3 a este Ministerio, no aparece suscrita la cesi\u00f3n del contrato No. 099 de 1996, por lo tanto no es procedente acceder a su petici\u00f3n\u201d.. Cfr. Escrito de tutela, p. 7. \u00a0<\/p>\n<p>3 Escrito de tutela, p. 8. \u00a0<\/p>\n<p>4 Escrito de tutela, p. 16. \u00a0<\/p>\n<p>5 Ib. \u00a0<\/p>\n<p>6 Cfr. sentencia del 13 de febrero de 2020 (fallo objeto de la acci\u00f3n de tutela).\u00a0 \u00a0<\/p>\n<p>8 Corte Suprema de Justicia, Sala de Casaci\u00f3n Civil, sentencia del 24 de julio de 2015, exp. 2004-00469-01. \u00a0<\/p>\n<p>9 Sentencia de tutela de primera instancia, p. 18. \u00a0<\/p>\n<p>10 Consejo de Estado, Secci\u00f3n Tercera. sentencia del 16 de marzo de 2015, expediente 73001-23-31-000-1999-03028 (exp. 31619). \u00a0<\/p>\n<p>11 Ib\u00edd. \u00a0<\/p>\n<p>12 Ib\u00edd. \u00a0<\/p>\n<p>13 Ib\u00edd. \u00a0<\/p>\n<p>14 Escrito de impugnaci\u00f3n, p. 8. \u00a0<\/p>\n<p>15 Ib\u00edd. \u00a0<\/p>\n<p>16 Sentencia de tutela de segunda instancia, p. 5. \u00a0<\/p>\n<p>17 Ib\u00edd. \u00a0<\/p>\n<p>18 Conformada por la magistrada Cristina Pardo Schlesinger y el magistrado Antonio Jos\u00e9 Lizarazo Ocampo. \u00a0<\/p>\n<p>19 La base argumentativa expuesta en este cap\u00edtulo hace parte de las Sentencias SU-917 de 2010, SU-195 de 2012, SU-515 de 2013, SU-769 de 2014, SU-336 de 2017, SU-072 de 2018, SU-116 de 2018 y T-016 de 2019. \u00a0<\/p>\n<p>20 Sentencias T-792 de 2010, T-511 de 2011, SU-773 de 2014 y SU-116 de 2018. \u00a0<\/p>\n<p>21 Convenci\u00f3n Americana sobre Derechos Humanos (art\u00edculo 25) y Pacto Internacional de Derechos Civiles y Pol\u00edticos (art\u00edculo 2). \u00a0<\/p>\n<p>22 Sentencia SU-116 de 2018. \u00a0<\/p>\n<p>23 Sentencias T-079 de 1993, T-231 de 1994, T-008 de 1998, T-260 de 1999 y SU-116 de 2018. \u00a0<\/p>\n<p>24 La base argumentativa expuesta en esta secci\u00f3n hace parte de la Sentencia C-590 de 2005 y SU-116 de 2018. \u00a0<\/p>\n<p>25 Sentencia SU-116 de 2018. \u00a0<\/p>\n<p>26 Sentencias SU-573 y SU-391 de 2016. Al respecto, la Corte sostuvo: \u201cConsidera la Corte que es improcedente la acci\u00f3n de tutela contra decisiones de la Corte Constitucional y, se agrega en esta oportunidad, contra decisiones del Consejo de Estado que resuelven acciones de nulidad por inconstitucionalidad. Esta ser\u00eda entonces una causal adicional de improcedencia que complementar\u00eda los requisitos generales de procedencia de la acci\u00f3n de tutela contra decisiones judiciales establecidos por la jurisprudencia a partir de la sentencia C-590 de 2005, de acuerdo con la cual no procede la acci\u00f3n de tutela contra las sentencias de la Corte Constitucional ni contra las del Consejo de Estado por nulidad por inconstitucionalidad\u201d. \u00a0<\/p>\n<p>27 Sentencias SU-573, SU-414 SU-396 y SU-354 de 2017; T-574, T-429 y T-324 de 2016; SU-695, SU-567, T-534 y T-718 de 2015, T-474 de 2014 y T-429 de 2011. \u00a0<\/p>\n<p>28 Este esquema de an\u00e1lisis de las causales generales de procedencia de la acci\u00f3n fue desarrollado por la Corte en la sentencia SU-573 de 2019. \u00a0<\/p>\n<p>29 Decreto 2591 de 1991 (art\u00edculos 5, 10 y 13). \u00a0<\/p>\n<p>30 Ley 1437 de 2011 (art\u00edculo 257).\u00a0 \u00a0<\/p>\n<p>31 Ley 1437 de 2011 (art\u00edculos 248 y siguientes). \u00a0<\/p>\n<p>32 Sentencias T-131 de 2021, SU-573 de 2019 y T-817 de 2012. \u00a0<\/p>\n<p>33 Sentencias T-131 de 2021, SU-573 de 2019, SU-573 de 2017, T-458 de 2016 y C-590 de 2005. \u00a0<\/p>\n<p>34 Sentencia T-137 de 2017. \u00a0<\/p>\n<p>35 Sentencias T-173 de 1993 y T-102 de 2006. \u00a0<\/p>\n<p>36 Sentencia T-335 de 2000.\u00a0 \u00a0<\/p>\n<p>37 Sentencia T- 102 de 2006. \u00a0<\/p>\n<p>38 Sentencia T-555 de 2019. Reiterada en la Sentencia SU-573 de 2019. \u00a0<\/p>\n<p>39 Sentencia C-590 de 2005. \u00a0<\/p>\n<p>40 Sentencias T-335 de 2000, T-1044 de 2007, T-658 de 2008, T-505 de 2009, T-610 de 2009, T-896 de 2010, T-040 de 2011, T-338 de 2012, T-512 de 2012, T-543 de 2012, T-1061 de 2012, T-931 de 2013, T-182 de 2014 y T-406 de 2014. \u00a0<\/p>\n<p>41 Sentencia C-590 de 2005. \u00a0<\/p>\n<p>42 Sentencia T-102 de 2006. \u00a0<\/p>\n<p>43 Sentencias SU-753 de 2019, T-555 de 2019 y T-248 de 2018. \u00a0<\/p>\n<p>44 Sentencia SU-753 de 2019. \u00a0<\/p>\n<p>45 Sentencias SU-753 de 2019 y SU-439 de 2017. \u00a0<\/p>\n<p>46 Sentencias SU-753 de 2019, SU-439 de 2017, SU-498 de 2016 y T-291 de 2016. \u00a0<\/p>\n<p>47 La Sentencia T-131 de 2021 analiz\u00f3 la procedencia de la acci\u00f3n de tutela contra laudos arbitrales. No obstante, las conclusiones se circunscriben a las subreglas que caracterizan el requisito de la relevancia constitucional. \u00a0<\/p>\n<p>48 Sentencias SU-753 de 2019, SU-439 de 2017, SU-498 de 2016 y T-291 de 2016. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>49 Sentencia SU-573 de 2019. \u00a0<\/p>\n<p>50 Sentencias SU-753 de 2019, SU-439 de 2017, SU-498 de 2016 y T-291 de 2016. \u00a0<\/p>\n<p>51 Sentencia T-173 de 1993. \u00a0<\/p>\n<p>52 Sentencias SU-753 de 2019, SU-439 de 2017, T-379 de 2007 y T-114 de 2002. \u00a0<\/p>\n<p>53 Sentencias SU-753 de 2019, SU-498 de 2016 y T-610 de 2015.\u00a0 \u00a0<\/p>\n<p>54 Sentencia T-136 de 2015. \u00a0<\/p>\n<p>55 Sentencia SU-336 de 2017.\u00a0 \u00a0<\/p>\n<p>56 Sentencia SU-573 de 2019. \u00a0<\/p>\n<p>57 Sentencia T-131 de 2021. \u00a0<\/p>\n<p>59 Sentencia SU-336 de 2017.\u00a0 \u00a0<\/p>\n<p>60 En igual sentido, se pronunci\u00f3 la Corte en las Sentencias T-121 de 2021, SU-573 de 2019, T-555 de 2019, T-422 de 2018, T-136 de 2015 y T-320 de 2012. \u00a0<\/p>\n<p>61 Sentencia SU-573 de 2019. \u00a0<\/p>\n<p>62 Sentencias SU573 de 2019, T-555 de 2019, SU-479 de 2019, T-248 de 2018, T-136 de 2015, T-136 de 2015, T-320 de 2012, C-590 de 2005, T-1318 de 2005, T-470 de 1998, T-524 de 1994, T-511 de 1993 y T-594 de 1992. \u00a0<\/p>\n<p>63 Sentencias T-635 de 2010 y T-586 de 2012. \u00a0<\/p>\n<p>64 Sentencia SU-573 de 2019. \u00a0<\/p>\n<p>65 Sentencias SU573 de 2019, T-555 de 2019, SU-479 de 2019, T-248 de 2018, T-136 de 2015, T-136 de 2015, T-320 de 2012 y C-590 de 2005. \u00a0<\/p>\n<p>66 Sentencia T-136 de 2015. \u00a0<\/p>\n<p>67 Sentencia SU-573 de 2019. \u00a0<\/p>\n<p>68 Sentencias SU-573 de 2019 y SU-072 de 2018. \u00a0<\/p>\n<p>69 Sentencias SU-753 de 2019 y SU-053 de 2015. \u00a0<\/p>\n<p>70 Sentencias SU-753 de 2019 y T-685 de 2003.\u00a0 \u00a0<\/p>\n<p>71 A conclusiones similares lleg\u00f3 la Corte en las Sentencias SU-573 de 2019 y T-555 de 2018.\u00a0 \u00a0<\/p>\n<p>72 Sentencia SU-573 de 2019. \u00a0<\/p>\n<p>73 Sentencias T-131 de 2021, SU-573 de 2019, T-102 de 2006. \u00a0<\/p>\n<p>74 Sentencia T-131 de 2021. \u00a0<\/p>\n<p>75 Sentencias T-310 de 2009 y T-902 de 2014. \u00a0<\/p>\n<p>76 Sentencias C-816 de 2011 y SU-053 de 2015. \u00a0<\/p>\n<p>77 M.P. Jos\u00e9 Fernando Reyes Cuartas. \u00a0<\/p>\n<p>78 M.P. Carlos Bernal Pulido. SV. Diana Fajardo Rivera. \u00a0<\/p>\n<p>79 Al respecto, la Sentencia SU-573 de 2019 se\u00f1al\u00f3 que \u201cen el evento en que se cuestione una sentencia dictada por una Alta Corte, el examen de la relevancia constitucional debe ser m\u00e1s estricto que el que pudiera hacerse en los dem\u00e1s eventos de procedencia de la acci\u00f3n de tutela contra providencias judiciales. En tales t\u00e9rminos, la acreditaci\u00f3n de esta exigencia,\u00a0m\u00e1s all\u00e1 de la mera adecuaci\u00f3n del caso a un lenguaje que exponga una relaci\u00f3n con derechos fundamentales, supone justificar\u00a0razonablemente la existencia de una restricci\u00f3n\u00a0prima facie\u00a0desproporcionada a un derecho fundamental, que no es lo mismo que una simple relaci\u00f3n con aquel.\u201d Esa mayor carga argumentativa del requisito de relevancia constitucional se sustent\u00f3 en la posici\u00f3n institucional del Consejo de Estado dado su car\u00e1cter de \u00f3rgano de cierre de la jurisdicci\u00f3n contenciosa administrativa y su competencia para unificar la jurisprudencia de su jurisdicci\u00f3n. \u00a0<\/p>\n<p>80 M.P. Carlos Bernal Pulido. SV. Diana Fajardo Rivera. \u00a0<\/p>\n<p>81 Ib\u00eddem. \u00a0<\/p>\n<p>82 M.P. Carlos Bernal Pulido. SV. Diana Fajardo Rivera. \u00a0<\/p>\n<p>83 En ese sentido, en el fundamento 95 la Sentencia T-267 de 2021 se\u00f1ala que la Sala \u201cno encuentra que la sentencia impugnada hubiere afectado el derecho a la igualdad del se\u00f1or N\u00e9stor Alfonso Guti\u00e9rrez\u201d y m\u00e1s adelanta sostiene que \u201c[l]a Corte revis\u00f3 la Sentencia del 13 de febrero de 2020 del Tribunal Administrativo de Cundinamarca. Esta determin\u00f3 que no hab\u00eda lugar al reconocimiento y pago de la cuota de \u00e9xito porque no se acredit\u00f3 que la cesi\u00f3n del contrato hubiere sido previa, expresa y escrita. Tal determinaci\u00f3n se fundament\u00f3 en la Ley 80 de 1993 y en la jurisprudencia del Consejo de Estado sobre la materia. La Secci\u00f3n Tercera tuvo en cuenta las pruebas que el actor aport\u00f3 para acreditar la cesi\u00f3n del contrato estatal, sin embargo, no le otorg\u00f3 el valor probatorio que el accionante pretend\u00eda, por cuanto ninguna de ellas supl\u00eda la exigencia legal. Esto quiere decir que el juez ordinario sustent\u00f3 su decisi\u00f3n de manera razonable y con base en las normas aplicables y las pruebas aportadas. De manera que, mal podr\u00eda concluirse que desconoci\u00f3 el debido proceso del actor.\u201d \u00a0<\/p>\n<p>84 Al respecto, el fallo cuestionado del Tribunal Administrativo de Cundinamarca se refiri\u00f3 al alcance que la Sentencia T-122 de 2017 (M.P. Luis Guillermo Guerrero P\u00e9rez) le dio a este postulado y puntualiz\u00f3 que \u201c[b]ajo ese entendimiento, para la Sala no es de recibo, que el demandante, que es abogado, pretenda desconocer sus deberes de cuidado, por cuanto, el presunto error de transcripci\u00f3n era una circunstancia que debi\u00f3 evidenciar al momento de la celebraci\u00f3n del contrato, toda vez, que cualquier argumento con posterioridad es aceptar, que se puede aprovechar de su propio error.\u201d De la misma manera, en la respuesta a la demanda de tutela la autoridad judicial accionada manifest\u00f3 que en el fallo atacado \u201cse hizo \u00e9nfasis, en la jurisprudencia de la H. Corte Constitucional, seg\u00fan la cual el Juez no puede amparar situaciones que derivan de una actuaci\u00f3n negligente de las propias partes, aspecto que precisamente se evidenciaba en el caso concreto (\u2026).\u201d\u00a0 \u00a0<\/p>\n<p>85 En relaci\u00f3n con los principios constitucionales de la contrataci\u00f3n p\u00fablica se puede consultar la Sentencia C-207 de 2019. M.P. Cristina Pardo Schlesinger. SV. Luis Guillermo Guerrero P\u00e9rez. SPV. Carlos Bernal Pulido y Alberto Rojas R\u00edos. AV. Diana Fajardo Rivera. Frente al principio \u201cno se escucha a quien alega su propia falta\u201d, adem\u00e1s de la Sentencia C-207 de 2019, se pueden consultar las sentencias T-122 de 2017 (M.P. Luis Guillermo Guerrero P\u00e9rez) y T-213 de 2008 (M.P. Jaime Araujo Renter\u00eda. SV. Manuel Jos\u00e9 Cepeda Espinosa), relativas a este principio en otros escenarios constitucionales. \u00a0<\/p>\n<p>86 Sentencia C-590 de 2005. M.P. Jaime C\u00f3rdoba Trivi\u00f1o. \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia T-267\/21 \u00a0 \u00a0\u00a0 ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Improcedencia por falta de relevancia constitucional y no evidenciar afectaci\u00f3n de derechos fundamentales \u00a0 \u00a0\u00a0 (\u2026) los argumentos expuestos por el actor, m\u00e1s all\u00e1 de exponer una cuesti\u00f3n iusfundamental, evidencian una discusi\u00f3n de orden legal y ante todo de evidente y claro contenido econ\u00f3mico. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130],"tags":[],"class_list":["post-27465","post","type-post","status-publish","format-standard","hentry","category-tutelas-2020"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/27465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=27465"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/27465\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=27465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=27465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=27465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}