{"id":27660,"date":"2024-07-02T20:38:30","date_gmt":"2024-07-02T20:38:30","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/07\/02\/t-426-21\/"},"modified":"2024-07-02T20:38:30","modified_gmt":"2024-07-02T20:38:30","slug":"t-426-21","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-426-21\/","title":{"rendered":"T-426-21"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia T-426\/21 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DEBIDO PROCESO DISCIPLINARIO EN ENTORNO UNIVERSITARIO-Vulneraci\u00f3n por demora injustificada en tr\u00e1mite de queja por acoso laboral y sexual\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(La accionada) no cumpli\u00f3 con el t\u00e9rmino razonable, de forma que se aseguraran los derechos fundamentales de la accionante. Por el contrario, se tard\u00f3 m\u00e1s de 3 a\u00f1os analizar el fondo de su denuncia, prolongando innecesariamente la indefinici\u00f3n de su queja. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DEBIDO PROCESO DISCIPLINARIO EN ENTORNO UNIVERSITARIO-Vulneraci\u00f3n por exceso ritual manifiesto\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(La accionada) neg\u00f3 la concesi\u00f3n del recurso de apelaci\u00f3n \u2026, bajo el argumento de que no se demostr\u00f3 la legitimaci\u00f3n de la apoderada \u2026 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>VIOLENCIA SEXISTA EN EL ENTORNO UNIVERSITARIO-Debida diligencia en la investigaci\u00f3n y sanci\u00f3n de violencias de g\u00e9nero \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>VIOLENCIA CONTRA LA MUJER-Instrumentos internacionales que hacen parte del bloque de constitucionalidad\/VIOLENCIA CONTRA LA MUJER-Obligaci\u00f3n del Estado de prevenir, investigar y sancionar con la diligencia debida \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>COMISION INTERAMERICANA DE DERECHOS HUMANOS Y CORTE INTERAMERICANA DE DERECHOS HUMANOS-Relaci\u00f3n entre deber del Estado a la debida diligencia y acceso a recursos judiciales id\u00f3neos y efectivos frente a la violencia contra la mujer \u00a0<\/p>\n<p>ADMINISTRACION DE JUSTICIA CON PERSPECTIVA DE GENERO-Forma de combatir la violencia contra la mujer \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ADMINISTRACION DE JUSTICIA CON PERSPECTIVA DE GENERO-Su desconocimiento por parte de quienes ejercen funciones judiciales, puede convertirse en un nuevo acto de violencia en contra de la mujer denunciante \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DISCRIMINACION Y VIOLENCIA CONTRA LA MUJER-Utilizaci\u00f3n de prejuicios y la actitud indiferente de los funcionarios de la Administraci\u00f3n de Justicia perpet\u00faa la violencia de g\u00e9nero \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DERECHO A UNA VIDA LIBRE DE VIOLENCIA Y PROHIBICI\u00d3N DE DISCRIMINACI\u00d3N EN EL ENTORNO UNIVERSITARIO-Obligaci\u00f3n de prevenir, sensibilizar, investigar y sancionar formas de violencia contra la mujer \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Se tienen que plantear mecanismos efectivos de investigaci\u00f3n y sanci\u00f3n que permitan que las instituciones educativas cumplan con su funci\u00f3n de ser espacios seguros. M\u00e1xime, cuando las universidades p\u00fablicas est\u00e1n sujetas, con mayor raz\u00f3n, al cumplimiento de las obligaciones estatales en el marco de los compromisos nacionales e internacionales en la prevenci\u00f3n y sanci\u00f3n de todas las formas de la violencia de g\u00e9nero. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>LEGITIMACION POR ACTIVA EN TUTELA-Abogado con poder para actuar \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>(\u2026), el an\u00e1lisis de la legitimaci\u00f3n por activa realizado por el juez de primera instancia de negar la calidad de sujeto procesal a la quejosa, desconoce abiertamente el enfoque de g\u00e9nero que exige que frente a estos casos en particular por su condici\u00f3n de v\u00edctima; las quejosas en estos procedimientos son sujetos procesales que gozan de las garant\u00edas del debido proceso. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Referencia: Expediente T-8.009.845 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Acci\u00f3n de tutela presentada por Alexi Viviana Amaya Cubillos en contra de la Veedur\u00eda Disciplinaria de la Universidad Nacional de Colombia \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Magistrado sustanciador: \u00a0<\/p>\n<p>ANTONIO JOS\u00c9 LIZARAZO OCAMPO \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Bogot\u00e1 D.C., tres (3) de diciembre de dos mil veintiuno (2021) \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La Sala Cuarta de Revisi\u00f3n de la Corte Constitucional1, en ejercicio de sus competencias constitucionales y legales, ha proferido la siguiente: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>SENTENCIA \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En el tr\u00e1mite de revisi\u00f3n del fallo dictado por el Tribunal Administrativo de Cundinamarca, Secci\u00f3n Tercera, Subsecci\u00f3n \u201cC\u201d, el 4 de septiembre de 2020, que confirm\u00f3 el proferido por el Juzgado 2 Administrativo del Circuito de Bogot\u00e1, el 30 de julio de 2020, dentro de la presente acci\u00f3n de tutela2.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. ANTECEDENTES \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Hechos probados3 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Alexi Viviana Amaya Cubillos se vincul\u00f3 a la Universidad Nacional en el a\u00f1o 2011 como contratista de la Facultad de Derecho en las dependencias de Acreditaci\u00f3n (entre febrero de\u00a02011 hasta el a\u00f1o 2012), doctorado de Derecho (entre febrero 2012 hasta diciembre de\u00a02014) y de Relaciones Internacionales desde diciembre de 2014. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Desde diciembre de 2014 y hasta el 31 de marzo de 2016, su jefe inmediato fue Jos\u00e9 Guillermo Castro Ayala, como Director del Proyecto de las Relaciones Internacionales (PRI) y docente de la Facultad de Derecho.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La accionante puso en conocimiento, a trav\u00e9s de una queja disciplinaria elevada el 20 de mayo de 2016, ante el Director del Comit\u00e9 de Convivencia Laboral de la Universidad Nacional, actos que configurar\u00edan acoso sexual y laboral de parte de Jos\u00e9 Guillermo Castro Ayala en su contra. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 25 de mayo de 2016, la Directora de Personal de la instituci\u00f3n remiti\u00f3 la queja disciplinaria a la Jefe de Acompa\u00f1amiento Integral, quien remiti\u00f3, el 12 de agosto de 2016, el tr\u00e1mite iniciado a la Veedur\u00eda Disciplinaria de la Universidad Nacional de Colombia. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La demandante radic\u00f3 ante la Procuradur\u00eda General de la Naci\u00f3n queja disciplinaria el 3 de junio de 2016. Esta la remiti\u00f3 al Comit\u00e9 de Convivencia laboral de la Universidad Nacional de Colombia para su estudio. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 1\u00b0 de septiembre de 2016, mediante auto 283 de 2016 se asign\u00f3 competencia para actuar a la Veedur\u00eda de la Universidad Nacional de Colombia, con la identificaci\u00f3n de TD- B \u2013 272 \u2013 2016. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Mediante auto B. OVD 832 de 16 de noviembre de 2016 la Veedur\u00eda Disciplinaria de la Universidad Nacional de Colombia orden\u00f3 abrir investigaci\u00f3n preliminar para establecer las circunstancias de tiempo, modo y lugar de ocurrencia de los hechos denunciados, notificar de la actuaci\u00f3n a los implicados y recaudar material probatorio relacionado con la vinculaci\u00f3n laboral de los sujetos procesales y escuchar en versi\u00f3n libre al denunciado4. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el auto B.OVD-438 de 6 de junio de 2017 se orden\u00f3 la apertura de investigaci\u00f3n disciplinaria, reconocer a la accionante como sujeto procesal y practicar como pruebas la declaraci\u00f3n juramentada del profesor Pablo Ignacio Reyes Beltr\u00e1n, la declaraci\u00f3n de ratificaci\u00f3n y ampliaci\u00f3n de la queja de la accionante y la remisi\u00f3n de antecedentes disciplinarios del denunciado5.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 26 de julio de 2017, mediante auto 0557 de 2017, la Veedur\u00eda Disciplinaria de la Universidad Nacional de Colombia reconoci\u00f3 personer\u00eda para actuar a la abogada Claudia Mej\u00eda Duque para actuar como apoderada de la demandante. Como suplente reconoci\u00f3 a Mar\u00eda Fernanda Herrera Burgos6 \u00a0 \u00a0<\/p>\n<p>1. En el auto 405 de 8 de mayo de 2019, la Veedur\u00eda Disciplinaria orden\u00f3 la terminaci\u00f3n del proceso y, en consecuencia, dispuso el archivo definitivo del tr\u00e1mite disciplinario. Indic\u00f3 que la Resoluci\u00f3n 1215 de 2017 proferida por la Rector\u00eda de la Universidad defin\u00eda el acoso sexual como:\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cAcoso, persecuci\u00f3n, hostigamiento o asedio f\u00edsico o verbal a una persona, con fines sexuales no consentidos. Se ejerce vali\u00e9ndose de la superioridad manifiesta o de relaciones de autoridad o de poder, edad, sexo, posici\u00f3n laboral, social, familiar o econ\u00f3mica\u201d.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De ah\u00ed que para la configuraci\u00f3n de la conducta debe existir el acoso, la persecuci\u00f3n, el hostigamiento o el asedio f\u00edsico o verbal, sumados a \u201cla existencia de: 1. El fin sexual por parte del presunto infractor. 2. Falta de consentimiento en trat\u00e1ndose de la presunta v\u00edctima. 3. Superioridad manifiesta o relaci\u00f3n de poder\u201d7. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Consider\u00f3, sobre la finalidad sexual, que el intercambio de comunicaciones entre el profesor y la demandante solo evidenciaban \u201creferencias sobre m\u00faltiples asuntos de \u00edndole personal y profesional de manera generalizada, sin que se observen contenidos sexuales expl\u00edcitos o impl\u00edcitos, solo algunas manifestaciones amigables\u201d8. Se trata de manifestaciones como \u201cchistes, bromas y comentarios propios de una amistad, en la que se observa un amplio margen de confianza de ambos extremos\u201d9. Adem\u00e1s, que esas formas de interacci\u00f3n \u201cfueron impl\u00edcitamente aceptadas por ambos sujetos procesales, sin que aparezca demostrada alguna objeci\u00f3n de estos frente a ellas\u201d10. Finalmente, que la percepci\u00f3n por parte de terceros desconoc\u00eda el contexto de familiaridad en que se daban las conversaciones.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sobre la falta de consentimiento, sostuvo que \u201cel lazo amistoso entre los sujetos procesales mut\u00f3 y adquiri\u00f3 matices particulares de confianza, cuyo desenlace fue el deterioro de la aparente amistad y la situaci\u00f3n conflictiva en que desemboc\u00f3\u201d11. Ese trato amistoso ajeno al trato institucional no implica necesariamente la existencia de acoso sexual. Aparece demostrada \u201cuna serie de comportamientos y conversaciones consentidas que resultan ajenas al obrar institucional y que se da entre dos personas adultas que concurrieron en espacios f\u00edsicos y virtuales con ocasi\u00f3n de sus actividades\u201d12. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sobre la superioridad manifiesta o relaci\u00f3n de poder, estim\u00f3 que de la designaci\u00f3n del docente como supervisor del contrato de prestaci\u00f3n de servicios de la accionante no pod\u00eda \u201cinferirse la existencia de una relaci\u00f3n jerarquizada dad la naturaleza estrictamente contractual de la ODS\u201d13. Adicionalmente, manifest\u00f3 que esa relaci\u00f3n profesional se dio entre noviembre de 2015 y enero de 2016 y culmin\u00f3 satisfactoriamente, descartando una supuesta superioridad.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por lo anterior, indic\u00f3 que no se encontraba probada objetivamente la ocurrencia de una conducta constitutiva de acoso sexual como forma de violencia basada en g\u00e9nero, por cuanto no se configuraron los tres elementos mencionados.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 21 de mayo de 2019, la Veedur\u00eda Disciplinaria neg\u00f3 esa solicitud, en tanto dentro del proceso hab\u00eda sido reconocida Claudia Mej\u00eda Duque para actuar como apoderada de la accionante y como suplente a Mar\u00eda Fernanda Herrera Burgos14. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 29 de mayo de 2019, se remiti\u00f3, v\u00eda correo electr\u00f3nico a la Veedur\u00eda Disciplinaria de la Universidad Nacional, la solicitud de copias del expediente, as\u00ed como dos poderes en los cuales designaba a la abogada Linda<\/p>\n<p>Mar\u00eda Cabrera Cifuentes y, esta, a su vez, otorgaba suplencia a\u00a0<\/p>\n<p>Mar\u00eda Camila Mart\u00ednez Galvis15. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 5 de junio de 2019, Mar\u00eda Camila Mart\u00ednez Galvis present\u00f3 recurso de apelaci\u00f3n en contra del auto 405 de 8 de mayo de 2019, al cual anex\u00f3 los poderes remitidos en el correo electr\u00f3nico anterior16. \u00a0 \u00a0<\/p>\n<p>1. Mediante auto 588 de 20 de junio de 2019, la Veedur\u00eda rechaz\u00f3<\/p>\n<p>el recurso de apelaci\u00f3n. Estableci\u00f3 que Mar\u00eda Camila Mart\u00ednez Galvis no<\/p>\n<p>contaba con legitimidad jur\u00eddica para actuar, debido a que la abogada suplente era\u00a0<\/p>\n<p>Linda Mar\u00eda Cabrera Cifuentes. En esa calidad, no pod\u00eda otorgar<\/p>\n<p>suplencia a la abogada Mar\u00eda Camila Mart\u00ednez, de conformidad con el art\u00edculo 123 de la Ley 906 de 200417.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 2 de julio de 2019, Linda Mar\u00eda Cabrera Cifuentes y Mar\u00eda Camila Mart\u00ednez presentaron recurso de queja en contra de la anterior decisi\u00f3n. Indicaron que los poderes hab\u00edan sido radicados desde el 29 de mayo de 2019, sin que la Veedur\u00eda hubiere expresado reparo alguno, raz\u00f3n por la cual \u201cla representaci\u00f3n no se percat\u00f3 del error mecanogr\u00e1fico en ellos y se entendi\u00f3 que estaban otorgados en debida forma\u201d. Explicaron que el art\u00edculo 23 del Acuerdo 171 de 2014 contiene el ejercicio del control de legalidad por el servidor p\u00fablico que dirige el tr\u00e1mite. Le correspond\u00eda al funcionario al momento de recibir los poderes remitidos v\u00eda correo electr\u00f3nico el 29 de mayo del presente a\u00f1o, esto es, una semana antes de la presentaci\u00f3n del recurso, pronunciarse sobre el presunto error, como hizo en ocasiones anteriores. Adem\u00e1s, que no darle tr\u00e1mite al recurso ni analizar de fondo los argumentos de la apelaci\u00f3n interpuesta supone un exceso de ritual manifiesto18. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Mediante Auto 695 de 23 de julio de 2019 la Veedur\u00eda confirm\u00f3 la negativa a conceder el recurso de apelaci\u00f3n. Explic\u00f3 que en materia disciplinaria la calidad de sujeto procesal solo est\u00e1 atribuida al investigado, a su defensor y al Ministerio P\u00fablico. Las v\u00edctimas y perjudicados por las faltas disciplinarias que constituyan violaciones del derecho internacional de derechos humanos y del Derecho Internacional Humanitario tambi\u00e9n son sujetos procesales, de conformidad con las sentencias C-014 de 2014 y C-487 de 2009. Aun cuando dentro de las facultades de los sujetos procesales distintos al investigado no est\u00e1 expresamente se\u00f1alada la de ser representado por apoderado, \u201cen sana l\u00f3gica nada impide que igualmente la intervenci\u00f3n del quejoso en aquellos casos en que pueda construirse como sujeto procesal\u201d19. En tanto la ley disciplinaria no prev\u00e9 \u201clos extremos de dicha postulaci\u00f3n\u201d, se debe acudir a la norma del art\u00edculo 3 del Acuerdo 171 de 2014 que remite al C\u00f3digo Disciplinario \u00danico, los c\u00f3digos General del Proceso, Administrativo y de lo Contencioso Administrativo, Penal y el de Procedimiento Penal, en coherencia con la naturaleza de este Estatuto Disciplinario. El CPACA\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201csolo hace referencia gen\u00e9rica al derecho de postulaci\u00f3n (art. 160) y el art. 75 del CGP, aun cuando se\u00f1ala que es posible que se otorgue poder a m\u00e1s de un abogado, no regula expresamente la figura del abogado suplente. Tal posibilidad, al parecer, solo tiene connotaci\u00f3n especial en el derecho penal, toda vez que el art\u00edculo 134 de la Ley 600 de 2000 (\u2026) la Ley 906 de 2004 a su vez, mantuvo dicha figura, pero solo la estableci\u00f3 para la defensa, de conformidad con los (\u2026) art\u00edculos [121 y 123]\u201d20. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Trasladando esa posibilidad al r\u00e9gimen disciplinario, \u201cla v\u00edctima podr\u00eda actuar directamente o a trav\u00e9s del apoderado a quien le confiri\u00f3 el poder y solo el apoderado de la defensa del investigado tendr\u00eda la posibilidad de nombrar apoderado suplente\u201d. No obstante, debido a que el funcionario acept\u00f3 la postulaci\u00f3n del apoderado suplente, resolvi\u00f3 el recurso presentado.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Explic\u00f3 que el fundamento f\u00e1ctico del recurso consiste en se\u00f1alar que existi\u00f3 \u201cun error mecanogr\u00e1fico\u201d y que la Veedur\u00eda no se\u00f1al\u00f3 inconsistencia alguna, por lo que se entendi\u00f3 que estaban otorgados en debida forma\u201d21. Advirti\u00f3 que, conforme con la copia del escrito de poder, es claro que la Claudia Mej\u00eda Duque, actuando como<\/p>\n<p>abogada principal, design\u00f3 como abogada suplente a la abogada Cabrera Cifuentes. Y que \u201ccarece de asidero la alegada existencia de un error mecanogr\u00e1fico en el documento de designaci\u00f3n enviado por correo electr\u00f3nico en fecha 29 de mayo de 2019, y posteriormente allegado en original en fecha 5 de junio, (fl. 761) junto con el escrito de recurso de apelaci\u00f3n por parte de la abogada Mar\u00eda Camita Mart\u00ednez Galvis\u201d22. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Adem\u00e1s, que el autocontrol de legalidad que le corresponde al funcionario competente de adelantar los procesos disciplinarios procede \u201cfrente a la generaci\u00f3n de<\/p>\n<p>alguna de las causales de nulidad del proceso, por posibles errores de las actuaciones o actos procesales, pero no frente a los documentos que por disposici\u00f3n de los sujetos procesales alleguen al mismo, y menos a\u00fan, como en este caso, sobre la existencia de un supuesto error, que de modo alguno deb\u00eda interpretar el funcionario de conocimiento\u201d23. Tampoco se configur\u00f3 un defecto procedimental por exceso ritual manifiesto, por cuanto se requiere de una irregularidad grave, que no se presenta en el caso. Esto, \u201ctoda vez que c\u00f3mo se ha se\u00f1alado, no existi\u00f3 ni existe un error en el documento en que la abogada principal designa como apoderada suplente a la Abogada Linda Mar\u00eda Cabrera Cifuentes, y que esta, al parecer con desconocimiento de la ley, prefiri\u00f3 omitir actuar en tal condici\u00f3n, como era su deber, prefiriendo a su vez tambi\u00e9n designar a otra abogada como \u2018Suplente\u2019 suya para que actuara en su reemplazo, lo que, si al caso demuestra, es un muy poco inter\u00e9s en la actuaci\u00f3n personal por parte (sic) la apoderada\u201d24. Finalmente, indic\u00f3 que no se desconoci\u00f3 alg\u00fan derecho fundamental a la accionante, en tanto intervino durante todo el proceso a trav\u00e9s de la apoderada suplente y que nunca se exigi\u00f3 el cumplimento de requisitos formales que pudieran constituir cargas imposibles de cumplimiento, ni un determinado rigorismo procedimental para la apreciaci\u00f3n de las pruebas que dieron lugar al archivo de proceso25. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Solicitud de tutela \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. A juicio de la actora, la Veedur\u00eda vulner\u00f3 sus derechos fundamentales al acceso a la justicia, al debido proceso, y a vivir una vida libre de violencias. Esto al i) no revisar de fondo el recurso de apelaci\u00f3n presentado en contra del auto 405 de 8 de mayo de 2019, ii) al instaurarse dicho recurso, no advertir el yerro procedimental en que pod\u00eda corregirse para revisar de fondo el recurso, iii) negar el recurso por un error de procedimiento aun cuando este se present\u00f3 con d\u00edas de anticipaci\u00f3n, con suficiente tiempo para haberse advertido alguna dificultad. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Esos errores imposibilitaron el acceso a la justicia, en tanto en el recurso de apelaci\u00f3n se se\u00f1alaba la falta de enfoque de g\u00e9nero, las irregularidades en<\/p>\n<p>la valoraci\u00f3n de la prueba y la inseguridad jur\u00eddica generada al sustentar el fallo en una norma que no estaba vigente para la \u00e9poca de los hechos. A su vez, permiti\u00f3 que la decisi\u00f3n de primera instancia quedara en firme, desconociendo su derecho a vivir una vida de violencias. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Respuesta de la entidad accionada \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 24 de julio de 2020, la Veedur\u00eda Disciplinaria de la Universidad Nacional de Colombia pidi\u00f3 que se desestimara el amparo. Consider\u00f3 que se buscaba debatir la legalidad de unas actuaciones surtidas en el decurso de un proceso disciplinario, surtido con todas las garant\u00edas sustanciales y procesales. Explic\u00f3 que el rechazo del recurso de apelaci\u00f3n obedeci\u00f3 a que fue presentado por Mar\u00eda Camila Mart\u00ednez Galvis, quien no ostentaba la calidad de apoderada suplente. Esa condici\u00f3n le correspond\u00eda a Linda Mar\u00eda Cabrera Cifuentes, seg\u00fan designaci\u00f3n de la apoderada de la accionante, situaci\u00f3n que fue explicada al resolver el recurso de queja.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El supuesto error en que incurri\u00f3 la apoderada de la accionante no puede ser atribuido al despacho, y menos ser tomado como una violaci\u00f3n al debido proceso, pues de ninguna manera se exigi\u00f3 el cumplimento de requisitos formales que pudieran constituir cargas imposibles de cumplimiento, o haber exigido un rigorismo procedimental inexistente en las normas procesales disciplinarias. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Decisi\u00f3n judicial objeto de revisi\u00f3n \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 30 de julio de 2020, el Juzgado 2 Administrativo del Circuito de Bogot\u00e1 declar\u00f3 improcedente el amparo. Sostuvo que la tutela cuestionaba una<\/p>\n<p>decisi\u00f3n dictada en el marco de un proceso disciplinario, del cual no es parte la<\/p>\n<p>legitimaci\u00f3n en la causa por activa para alegar la vulneraci\u00f3n de derecho alguno en<\/p>\n<p>el aludido proceso. Si en gracia de discusi\u00f3n se aceptara su legitimaci\u00f3n, indic\u00f3 que no se cumpl\u00eda el requisito de inmediatez, porque la inconformidad presentada por la accionante se deriv\u00f3 de la expedici\u00f3n de un acto administrativo fechado el 20 de junio de 2019, es decir, un a\u00f1o atr\u00e1s. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 4 de septiembre de 2020 el Tribunal Administrativo de Cundinamarca, Secci\u00f3n Tercera, Subsecci\u00f3n \u201cC\u201d confirm\u00f3 la improcedencia del amparo, no obstante, consider\u00f3 cumplida la legitimaci\u00f3n por activa.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Actuaciones en sede de revisi\u00f3n \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Allegaron Amicus Curiae la Corporaci\u00f3n Colectivo de Abogados Jos\u00e9 Alvear Restrepo (CAJAR)26, la Mesa por el Derecho de las Mujeres a una Vida Libre de Violencias27, la Corporaci\u00f3n Humanas28, la L\u00ednea de Investigaci\u00f3n de Feminismos, G\u00e9nero y Poder del Grupo de Investigaci\u00f3n Te\u00f3rica Pol\u00edtica Contempor\u00e1nea de la Universidad Nacional de Colombia29, coadyuvando la pretensi\u00f3n de la accionante. En general, indicaron que: \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>i. A pesar de la existencia de mecanismos de denuncia de acoso al interior de las universidades, la falta de resultados conduce a la no presentaci\u00f3n de denuncias y a la persistencia de los hechos de violencia en el \u00e1mbito educativo, \u00a0\u00a0<\/p>\n<p>ii. La Universidad Nacional de Colombia public\u00f3 una investigaci\u00f3n en 2016 en la que se evidenci\u00f3 que el 54% de las estudiantes encuestadas hab\u00eda sido v\u00edctima de alg\u00fan tipo de violencia sexual en el campus o en actividades relacionadas con la universidad,\u00a0 \u00a0\u00a0<\/p>\n<p>iii. Las pr\u00e1cticas de la Veedur\u00eda Disciplinaria suponen una violencia institucional que impiden en la pr\u00e1ctica las denuncias por acoso y que se debe flexibilizar el requisito de inmediatez. Entre ellas destacaron la falta de cumplimiento de un plazo razonable, pues la queja fue presentada el 20 de mayo de 2016 y esta fue remitida al \u00f3rgano competente 3 meses despu\u00e9s, este se tom\u00f3 m\u00e1s de un a\u00f1o para dar apertura a la investigaci\u00f3n y cinco meses m\u00e1s para que asumiera la investigaci\u00f3n del caso. Despu\u00e9s de 3 a\u00f1os, se archiv\u00f3 su proceso. Mientras tanto, la accionante vio afectada su vida laboral, puesto que tuvo que ser trasladada de lugar de trabajo y su caso a\u00fan sigue siendo conversaci\u00f3n habitual en la instituci\u00f3n. Tambi\u00e9n mencionaron la falta de control de legalidad de la representaci\u00f3n legal de la accionada en el caso del recurso, cuando este control hab\u00eda sido ejercido en ocasiones anteriores.\u00a0 \u00a0\u00a0<\/p>\n<p>iv. El auto que orden\u00f3 el archivo desconoci\u00f3 la relaci\u00f3n de poder entre la accionante y el docente, desestimando la gravedad de las pruebas allegadas y calificando las conversaciones como propias de una amistad cercana. \u00a0\u00a0<\/p>\n<p>v. No hab\u00eda lugar a la aplicaci\u00f3n del art\u00edculo 123 del C\u00f3digo de Procedimiento Penal, en tanto no es la primera remisi\u00f3n del Acuerdo 171 de 2014. Ni el CPACA ni el CGP contemplan una prohibici\u00f3n respecto de la suplencia del poder. Simplemente, se proh\u00edbe la actuaci\u00f3n simultanea de dos apoderados, y el CGP permite la sustituci\u00f3n de poder siempre que no est\u00e9 expresamente prohibido. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Particularmente, frente a la interpretaci\u00f3n de la Veedur\u00eda Disciplinaria frente a la sustituci\u00f3n de poderes, y su relaci\u00f3n con la violaci\u00f3n al debido proceso, se destaca la intervenci\u00f3n del Colectivo de Abogados Jos\u00e9 Alvear Restrepo (CAJAR)30 en cuanto a lo siguiente: \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>i. La Veedur\u00eda como entidad que debe aplicar el marco jur\u00eddico incumpli\u00f3 su obligaci\u00f3n de adoptar medidas integrales para cumplir con la debida diligencia en casos de violencia contra las mujeres. \u00a0\u00a0<\/p>\n<p>ii. A la vez, perpet\u00faan un estado de violencia institucional y discriminaci\u00f3n en el desarrollo del proceso disciplinario. El da\u00f1o en concreto consiste en la p\u00e9rdida de la oportunidad de analizar la controversia de fondo. \u00a0\u00a0<\/p>\n<p>iii. El exceso ritual manifiesto deviene en una denegaci\u00f3n de justicia, a trav\u00e9s de la prevalencia de la forma sobre el fondo. \u00a0\u00a0<\/p>\n<p>iv. Entre dos posibles interpretaciones respecto a la norma procesal, debe adoptarse aquella que no resulte lesiva para los derechos de la demandante y con el orden constitucional.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0CONSIDERACIONES \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Planteamiento del problema jur\u00eddico \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. \u00a0 \u00a0Corresponde a la Sala resolver el siguiente problema jur\u00eddico: \u00bfla Veedur\u00eda Disciplinaria de la Universidad Nacional de Colombia viol\u00f3 los derechos fundamentales de la demandante a una vida libre de violencia para las mujeres, al debido proceso y al acceso a la justicia al rechazar el recurso de apelaci\u00f3n contra el auto que archiv\u00f3 la investigaci\u00f3n disciplinaria por hechos relacionados con acoso sexual y laboral con fundamento en la no acreditaci\u00f3n de legitimidad para actuar a la abogada que formula el recurso? \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Plan de decisi\u00f3n \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. Desde ya se advierte que la Veedur\u00eda Disciplinaria de la Universidad Nacional desconoci\u00f3 los derechos al debido proceso y al acceso a la justicia de Alexi Viviana Amaya Cubillos, al negar la concesi\u00f3n del recurso de apelaci\u00f3n en contra del auto 588 de 20 de junio de 2019. Esto, bajo el argumento de que no se demostr\u00f3 la legitimaci\u00f3n de la apoderada para presentarla, en tanto esta hab\u00eda sido designada como suplente de la suplente de la apoderada. A efectos de motivar tal decisi\u00f3n, la Sala i) expondr\u00e1 el cumplimiento de los requisitos de procedibilidad, y ii) reiterar\u00e1 la necesidad de proveer recursos efectivos a las mujeres que denuncien actos de violencia en todos los \u00e1mbitos.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Requisitos de procedibilidad \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El caso cumple con el requisito de legitimaci\u00f3n en la causa31. Con relaci\u00f3n a la legitimaci\u00f3n en la causa por activa, se encuentra que la acci\u00f3n de tutela fue presentada por la apoderada de la titular de los derechos fundamentales que se invocan vulnerados. Dicha representaci\u00f3n se desarroll\u00f3 en virtud de sustituci\u00f3n de poder enviada por el medio procedente y radicada ante la autoridad competente, la cual, guard\u00f3 silencio ante la solicitud a pesar de haberse radicado dentro de un t\u00e9rmino razonable. Este control de legalidad corresponde al director del proceso disciplinario, control que se omiti\u00f3 y no puede traducirse en una disminuci\u00f3n de las garant\u00edas procesales.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En cuanto a la legitimaci\u00f3n por pasiva, la tutela se dirige en contra de la Veedur\u00eda Disciplinaria de la Universidad Nacional, quien fue la entidad que neg\u00f3 la concesi\u00f3n del recurso de apelaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El caso cumple el requisito de subsidiariedad. De conformidad con lo previsto en los art\u00edculos 86 de la Constituci\u00f3n y 6 del Decreto 2591 de 1991, la tutela cumple el requisito de subsidiariedad: i) cuando el accionante no dispone de un medio ordinario de defensa judicial, o ii) a pesar de este, se utiliza para evitar la configuraci\u00f3n de un perjuicio irremediable. Al respecto se advierte que no existe otro mecanismo de defensa para cuestionar el archivo del proceso disciplinario que pueda satisfacer de igual manera los derechos fundamentales que se pretenden.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En esta medida cabe aclarar que contra los actos administrativos de naturaleza particular, como el presente, en los que se lesione un derecho subjetivo amparado en una norma jur\u00eddica, puede solicitarse la acci\u00f3n de nulidad y restablecimiento del derecho en los t\u00e9rminos del art\u00edculo 136 del CPACA. Sin embargo, la tutela procede de manera excepcional cuando: (i) se est\u00e9 ante un perjuicio inminente, (ii) el perjuicio sea grave y conlleve la afectaci\u00f3n de un bien susceptible de determinaci\u00f3n jur\u00eddica altamente significativo para la persona, (iii) se requieran medidas urgentes para superar el da\u00f1o y (iv) las medidas de protecci\u00f3n respondan a condiciones de oportunidad y eficacia para evitar la consumaci\u00f3n del da\u00f1o irreparable. El caso en concreto presenta una necesidad de proteger el derecho fundamental a una vida libre de violencias en el marco del desarrollo del ejercicio laboral al interior del ambiente universitario.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El caso cumple el requisito de inmediatez. La valoraci\u00f3n del cumplimiento del requisito de inmediatez depende de las circunstancias particulares de cada caso, pues este no tiene un t\u00e9rmino expreso de caducidad. La jurisprudencia ha se\u00f1alado diferentes criterios para definir si el lapso entre los hechos que se dicen violatorios de derechos fundamentales y la solicitud de amparo atiende a la finalidad de la acci\u00f3n de tutela, es decir, ser un mecanismo excepcional y expedito. En el caso el demandante present\u00f3 la tutela el 1 de junio de 2020 y la decisi\u00f3n final de rechazo del recurso se dio mediante auto 695 de 23 de julio de 2019. Entre el auto y el amparo transcurrieron once meses, t\u00e9rmino que se estima razonable bajo el entendido de que en los casos en los que hay violencia contra la mujer, debe haber una flexibilizaci\u00f3n de le los requisitos de procedencia formal de la tutela en aras de no vaciar de contenido el derecho fundamental que se pretende proteger. Adicionalmente, se tiene que desde marzo de 2020 se declar\u00f3 la emergencia social por la pandemia del Covid-19. En ese marco, se suspendieron temporalmente las labores de los juzgados y se modificaron las formas de presentar las tutelas, a trav\u00e9s de medios tecnol\u00f3gicos. Esa situaci\u00f3n debe ser atendida al momento de evaluar el periodo transcurrido.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Agotado el an\u00e1lisis de procedibilidad de la acci\u00f3n de tutela, procede la Sala de Revisi\u00f3n a pronunciarse de fondo. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Las universidades tienen la obligaci\u00f3n de proveer mecanismos efectivos para la sensibilizaci\u00f3n, la prevenci\u00f3n y la sanci\u00f3n de formas de violencia y discriminaci\u00f3n contra las mujeres \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Al respecto de los deberes de las autoridades que conocen casos de violencia en contra de las mujeres, la Corte Constitucional ha incorporado dentro de su jurisprudencia los est\u00e1ndares derivados de la\u00a0Convenci\u00f3n sobre la eliminaci\u00f3n de todas las formas de discriminaci\u00f3n contra la mujer\u00a0(CEDAW), la\u00a0Convenci\u00f3n Interamericana para prevenir, sancionar y erradicar la violencia contra la mujer\u00a0(Convenci\u00f3n de Belem do Par\u00e1), el Pacto Internacional de Derechos Civiles y Pol\u00edticos y la\u00a0Convenci\u00f3n Americana sobre Derechos Humanos para determinar el alcance de las obligaciones estatales en cuanto a la prevenci\u00f3n, investigaci\u00f3n, sanci\u00f3n y reparaci\u00f3n de la violencia contra la mujer, al considerar que ellos hacen parte del bloque de constitucionalidad33. Adicional a ello, se tiene que la citada Ley 1257 de 2008, en su art\u00edculo 4, se\u00f1ala que esos compromisos son gu\u00eda para su interpretaci\u00f3n y aplicaci\u00f3n en relaci\u00f3n con todas las medidas de sensibilizaci\u00f3n, prevenci\u00f3n y sanci\u00f3n de formas de violencia y discriminaci\u00f3n contra las mujeres.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Entre los est\u00e1ndares en los que este Tribunal ha insistido se encuentran i) el derecho a acceder a un recurso judicial sencillo y eficaz y ii) el deber estatal de diligencia en la prevenci\u00f3n, investigaci\u00f3n, sanci\u00f3n y reparaci\u00f3n de la violencia contra las mujeres. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El derecho de las mujeres a acceder a un recurso judicial sencillo y eficaz que cuente con las debidas garant\u00edas cuando denuncian hechos de violencia, se deriva de los art\u00edculos XVIII34 de la Declaraci\u00f3n Americana, y 835 y 2536 de la Convenci\u00f3n Americana. Para la Comisi\u00f3n Interamericana de Derechos Humanos esa prerrogativa implica \u201cel derecho de todo individuo de acceder a un tribunal cuando alguno de sus derechos haya sido violado -sea \u00e9ste un derecho protegido por la Convenci\u00f3n, la Constituci\u00f3n o las leyes internas del Estado- de obtener una investigaci\u00f3n judicial a cargo de un tribunal competente, imparcial e independiente en la que se establezca la existencia o no de la violaci\u00f3n y se fije, cuando corresponda, una compensaci\u00f3n adecuada\u201d37. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El deber de implementar un recurso efectivo no se reduce a la mera existencia de los tribunales, la consagraci\u00f3n formal de los procedimientos o la posibilidad de recurrir a los tribunales, sino que los recursos judiciales deben ser efectivos38, esto es, deben ser capaces de \u201cproducir resultados o respuestas a las violaciones de derechos contemplados en la Convenci\u00f3n\u201d39. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Espec\u00edficamente, en cuanto al deber de investigar se ha indicado que no se puede tomar como \u201cuna simple formalidad condenada de antemano a ser infructuosa, o como una mera gesti\u00f3n de intereses particulares, que dependa de la iniciativa procesal de las v\u00edctimas o de sus familiares o de la aportaci\u00f3n privada de elementos probatorios\u201d42. Adem\u00e1s, exige: \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>i. adelantar una investigaci\u00f3n seria, oportuna, completa e imparcial, que use todos los medios legales disponibles y est\u00e9 orientada a la determinaci\u00f3n de la verdad43;\u00a0 \u00a0\u00a0<\/p>\n<p>ii. fortalecer\u00a0la capacidad institucional para combatir el patr\u00f3n de impunidad frente a casos de violencia contra las mujeres a trav\u00e9s de investigaciones criminales efectivas que tengan un seguimiento judicial consistente;\u00a0 \u00a0\u00a0<\/p>\n<p>iii. garantizar una capacitaci\u00f3n efectiva en materia de derechos de las mujeres, de todos los funcionarios p\u00fablicos involucrados en el procesamiento en estos casoshttp:\/\/www.corteconstitucional.gov.co\/relatoria\/2016\/t-265-16.htm &#8211; _ftn55;\u00a0 \u00a0\u00a0<\/p>\n<p>iv. institucionalizar la colaboraci\u00f3n y el intercambio de informaci\u00f3n entre las autoridades responsables de investigar los actos de violencia y discriminaci\u00f3n; y\u00a0 \u00a0\u00a0<\/p>\n<p>v. dise\u00f1ar\u00a0protocolos para facilitar y fomentar la efectiva, uniforme y transparente investigaci\u00f3n de actos de violencia f\u00edsica, sexual y psicol\u00f3gica, que incluya una descripci\u00f3n de la complejidad en las pruebas, y el detalle de las pruebas m\u00ednimas que es preciso recopilar para proporcionar una fundamentaci\u00f3n probatoria adecuada, que incluya pruebas cient\u00edficas, psicol\u00f3gicas, f\u00edsicas y testimoniales44. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Con base en esos est\u00e1ndares, en el sistema interamericano se ha entendido que la ineficacia judicial en casos de violencia contra las mujeres \u201cpropicia un ambiente de impunidad que facilita y promueve la repetici\u00f3n de los hechos de violencia en general y env\u00eda un mensaje seg\u00fan el cual la violencia contra las mujeres puede ser tolerada y aceptada como parte del diario vivir\u201d45. Para la Comisi\u00f3n la tolerancia estatal es una pauta sistem\u00e1tica en relaci\u00f3n con la violencia contra las mujeres, que \u201cperpetua[ba] las ra\u00edces y factores psicol\u00f3gicos, sociales e hist\u00f3ricos que mantienen y alimentan la violencia contra la mujer\u201d46. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Adem\u00e1s, se ha considerado que las fallas en la prevenci\u00f3n, investigaci\u00f3n, sanci\u00f3n y reparaci\u00f3n de la violencia en contra de la mujer pueden convertir al Estado en responsable de la misma, en tanto la situaci\u00f3n de impunidad promueve la repetici\u00f3n de las agresiones. Esa responsabilidad puede estar dada por el desconocimiento de su obligaci\u00f3n de no discriminaci\u00f3n, que se da cuando las autoridades consideran que la violencia no es un \u201cproblema de magnitud importante para el cual se requ[ieren] acciones inmediatas y contundentes\u201d, raz\u00f3n por la cual se niegan a investigarla47. Para la Corte, la indiferencia de las autoridades en la investigaci\u00f3n conduce a la impunidad, lo que a su vez \u201creproduce la violencia que se pretende atacar, sin perjuicio de que constituye en s\u00ed misma una discriminaci\u00f3n en el acceso a la justicia\u201d. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Adem\u00e1s de los est\u00e1ndares enunciados, este Tribunal ha subrayado que la violencia contra la mujer tiene un v\u00ednculo directo con el contexto hist\u00f3rico de discriminaci\u00f3n que han sufrido las mujeres, debido a que se trata de un medio para perpetuar su subordinaci\u00f3n al hombre en el \u00e1mbito familiar48. Por esa raz\u00f3n, no se trata de un fen\u00f3meno dom\u00e9stico que deba ser abordado en la privacidad del hogar, sino que exige compromisos de parte del Estado y de la sociedad en su conjunto para eliminar sus causas estructurales, de forma que se permita la materializaci\u00f3n del derecho fundamental de las mujeres a vivir libres de violencia y de discriminaci\u00f3n49. Al respecto, ha considerado que esa violencia hace parte de un contexto estructural de violencia que ha permeado los \u00e1mbitos pol\u00edticos, social y econ\u00f3mico, por las agresiones f\u00edsicas, psicol\u00f3gicas y econ\u00f3micas de las que son v\u00edctimas \u201cse tolera[n] sin que haya una reacci\u00f3n social o estatal eficaz\u201d50.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Dentro de ese contexto, se incluyen tambi\u00e9n las actuaciones de distintos operadores judiciales, quienes toman decisiones con fundamento en actitudes sociales discriminatorias que perpet\u00faan la impunidad para los actos de violencia contra la mujer51. Justamente, esta Corporaci\u00f3n ha se\u00f1alado que \u201cuna de las mayores limitaciones que las mujeres encuentran para denunciar la violencia, en especial la dom\u00e9stica y la psicol\u00f3gica, es la tolerancia social a estos fen\u00f3menos, que implica a su vez la ineficacia de estos procesos y las dificultades probatorias a las que se enfrenta la administraci\u00f3n de justicia frente a estos casos\u201d52. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Consciente del rol esencial que desempe\u00f1an los funcionarios en la erradicaci\u00f3n de la violencia contra la mujer y en la subsistencia de patrones discriminatorios y estereotipos de g\u00e9nero en el desarrollo de los procesos judiciales53, este Tribunal ha enunciado un m\u00ednimo de condiciones para asegurar el acceso a una justicia con perspectiva de g\u00e9nero, a saber: \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>i. desplegar toda actividad investigativa en aras de garantizar los derechos en disputa y la dignidad de las mujeres;\u00a0 \u00a0\u00a0<\/p>\n<p>ii. analizar los hechos, las pruebas y las normas con base en interpretaciones sistem\u00e1ticas de la realidad, de manera que en ese ejercicio hermen\u00e9utico se reconozca que las mujeres han sido un grupo tradicionalmente discriminado y como tal, se justifica un trato diferencial;\u00a0 \u00a0\u00a0<\/p>\n<p>iii. no tomar decisiones con base en estereotipos de g\u00e9nero;\u00a0 \u00a0\u00a0<\/p>\n<p>iv. evitar la revictimizaci\u00f3n de la mujer a la hora de cumplir con sus funciones; reconocer las diferencias entre hombres y mujeres;\u00a0 \u00a0\u00a0<\/p>\n<p>v. flexibilizar la carga probatoria en casos de violencia o discriminaci\u00f3n, privilegiando los indicios sobre las pruebas directas, cuando estas \u00faltimas resulten insuficientes;\u00a0 \u00a0\u00a0<\/p>\n<p>vi. considerar el rol transformador o perpetuador de las decisiones judiciales; \u00a0\u00a0<\/p>\n<p>vii. efectuar un an\u00e1lisis r\u00edgido sobre las actuaciones de quien presuntamente comete la violencia;\u00a0 \u00a0\u00a0<\/p>\n<p>viii. evaluar las posibilidades y recursos reales de acceso a tr\u00e1mites judiciales; \u00a0\u00a0<\/p>\n<p>ix. analizar las relaciones de poder que afectan la dignidad y autonom\u00eda de las mujeres. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ahora bien, las faltas a los anteriores deberes por parte de quienes ejercen funciones judiciales no solo desconocen las obligaciones de disponer de un recurso judicial efectivo y de actuar con la debida diligencia, sino que pueden convertirse en un nuevo acto de violencia en contra de la mujer denunciante54, cuando la acci\u00f3n u omisi\u00f3n estatal \u201ccause muerte, da\u00f1o o sufrimiento f\u00edsico, sexual, psicol\u00f3gico, econ\u00f3mico o patrimonial por su condici\u00f3n de mujer, as\u00ed como las amenazas de tales actos\u201d, a la luz de la citada Ley 1257 de 200855. Ello obedece al compromiso del Estado en la superaci\u00f3n del contexto de violencia mencionado y su obligaci\u00f3n de protecci\u00f3n reforzada. Al respecto, se precisa que esa norma contempla que la violencia puede darse en el \u00e1mbito p\u00fablico o privado56 y que la Declaraci\u00f3n sobre la eliminaci\u00f3n de la violencia contra la mujer y la Convenci\u00f3n Bel\u00e9m Do Par\u00e1 establecen que tambi\u00e9n se entiende como violencia contra la mujer la perpetrada o tolerada por el Estado o sus agentes57 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El incumplimiento de estos deberes por parte de las autoridades ponen de manifiesto la asimilaci\u00f3n de estereotipos de g\u00e9nero y de pr\u00e1cticas sociales que llevan inmersa una subordinaci\u00f3n de las mujeres, y consolidan actos de discriminaci\u00f3n. Sisma Mujer, en su intervenci\u00f3n en el proceso, sostuvo que la parte visible de esa violencia consist\u00eda en la tolerancia e ineficacia institucional que imped\u00eda a las mujeres acceder a la justicia, y la parte invisible se refer\u00eda a los actos y omisiones de los funcionarios que ocasionan da\u00f1o. Se trata de una violencia que puede resultar a\u00fan m\u00e1s perjudicial que la perpetrada por un particular, en tanto estos act\u00faan con la legitimidad y legalidad que emana de la investidura como autoridad p\u00fablica y que refuerza el discurso del agresor58. Adicionalmente, por tratarse de pr\u00e1cticas invisibles que han sido interiorizadas por los operadores y las mujeres que son v\u00edctimas de ellas, no son denunciadas. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ahora bien, en cuanto al abordaje de la violencia sexual dentro de las universidades, se tiene que esta debe cumplir con los mismos par\u00e1metros esbozados antes. Se tienen que plantear mecanismos efectivos de investigaci\u00f3n y sanci\u00f3n que permitan que las instituciones educativas cumplan con su funci\u00f3n de ser espacios seguros. M\u00e1xime, cuando las universidades p\u00fablicas est\u00e1n sujetas, con mayor raz\u00f3n, al cumplimiento de las obligaciones estatales en el marco de los compromisos nacionales e internacionales en la prevenci\u00f3n y sanci\u00f3n de todas las formas de la violencia de g\u00e9nero.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para la Sala de Revisi\u00f3n es claro que el proceso desarrollado por la Veedur\u00eda Disciplinaria no cumpli\u00f3 con el t\u00e9rmino razonable, de forma que se aseguraran los derechos fundamentales de la accionante. Por el contrario, se tard\u00f3 m\u00e1s de 3 a\u00f1os analizar el fondo de su denuncia, prolongando innecesariamente la indefinici\u00f3n de su queja. Para este Tribunal en los casos de violencia contra mujeres la falta de determinaci\u00f3n judicial genera una \u201camenaza seria, real y protuberante de los derechos fundamentales (\u2026) toda vez que la demora en la adopci\u00f3n de decisiones puede devenir en la vulneraci\u00f3n irremediable de los derechos a la integridad personal, a la familia, a la libertad y a la vida en condiciones dignas\u201d59. La efectividad del tr\u00e1mite depende de la rapidez en la cual se sancionen los actos, de manera que se erradique la violencia o la amenaza de ella, as\u00ed como de la posibilidad real de que la mujer pueda hacer cumplir las \u00f3rdenes dictadas ante la autoridad competente una vez estas hayan sido infringidas. Desatender ese car\u00e1cter urgente afecta los derechos a disponer de un recurso judicial efectivo y a obtener una decisi\u00f3n en un plazo razonable, as\u00ed como desconoce la obligaci\u00f3n estatal de garantizar que no se repitan las agresiones, \u201cbien sea porque pueda ser objeto de nuevos ataques por la misma persona o porque pueda ser objeto de retaliaciones por denunciarlos\u201d60. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por ende, la prontitud en la administraci\u00f3n de justicia constituye una garant\u00eda esencial de los derechos fundamentales al debido proceso y al acceso a la justicia, pero no todo retardo en la decisi\u00f3n supone una infracci\u00f3n a la Constituci\u00f3n. Esa situaci\u00f3n solo se da cuando se compruebe que este se dio por falta de diligencia del funcionario o que el plazo del proceso es irrazonable, al analizar las especificidades del caso61, que en los casos de violencia contra las mujeres deben ser analizadas con mayor rigor por la necesidad de adoptar medidas urgentes que eviten el riesgo de reincidencia de la violencia.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De otro lado, se tiene que dentro del proceso el funcionario encargado realiz\u00f3 control de legalidad a los poderes durante el transcurso del proceso. Sin embargo, de cara a los \u00faltimos poderes allegados no realiz\u00f3 esa facultad y, por el contrario, con base en las faltas de esos documentos decidi\u00f3 rechazar el recurso en contra de la decisi\u00f3n de fondo sobre la queja. Se advierte que la decisi\u00f3n adoptada por la accionada se fund\u00f3 en una aplicaci\u00f3n inadecuada de la norma de remisi\u00f3n del Acuerdo 171 de 2014. Es as\u00ed como consider\u00f3 que el silencio del CPACA y del CGP en cuanto a la suplencia de poderes, conduc\u00eda innecesariamente a aplicar la prohibici\u00f3n del C\u00f3digo de Procedimiento Penal, sin entrar a considerar que la falta de prohibici\u00f3n de los estatutos civil y administrativo daba cuenta de la autorizaci\u00f3n de la suplencia. Dicha aplicaci\u00f3n condujo a un defecto procedimental por exceso ritual manifiesto y al desconocimiento del derecho sustancial de la mujer de contar con un mecanismo efectivo de defensa ante actos de violencia de g\u00e9nero. Por consiguiente, se dejar\u00e1 sin efectos la providencia que neg\u00f3 la concesi\u00f3n del recurso de apelaci\u00f3n.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por \u00faltimo, el an\u00e1lisis de la legitimaci\u00f3n por activa realizado por el juez de primera instancia de negar la calidad de sujeto procesal a la quejosa, desconoce abiertamente el enfoque de g\u00e9nero que exige que frente a estos casos en particular por su condici\u00f3n de v\u00edctima; las quejosas en estos procedimientos son sujetos procesales que gozan de las garant\u00edas del debido proceso. Dicha calidad fue correctamente reconocida por el juez de segunda instancia y adicionalmente, en el tr\u00e1mite disciplinario N\u00baTD-B-272-2016.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Cuarta de Revisi\u00f3n de la Corte Constitucional, administrando justicia en nombre del pueblo y por mandato de la Constituci\u00f3n, \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>PRIMERO.- REVOCAR la sentencia dictada por el Tribunal Administrativo de Cundinamarca, Secci\u00f3n Tercera, Subsecci\u00f3n \u201cC\u201d, el 4 de septiembre de 2020, que confirm\u00f3 el proferido por el Juzgado 2 Administrativo del Circuito de Bogot\u00e1, el 30 de julio de 2020. En su lugar, CONCEDER el amparo de los derechos fundamentales al debido proceso y al acceso a la administraci\u00f3n de justicia de Alexi Viviana Amaya Cubillos. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>SEGUNDO-. DEJAR SIN EFECTOS el auto 588 de 20 de junio de 2019, proferido por la Veedur\u00eda Disciplinaria de la Universidad Nacional de Colombia, que rechaz\u00f3 el recurso de apelaci\u00f3n en contra del auto 405 de 8 de mayo de 2019.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>TERCERO.- ORDENAR a la Veedur\u00eda Disciplinaria de la Universidad Nacional de Colombia que dentro de los veinte (20) d\u00edas siguientes a la notificaci\u00f3n del presente fallo, d\u00e9 tr\u00e1mite al recurso propuesto y analice, con perspectiva de g\u00e9nero y atendiendo los est\u00e1ndares internacionales, constitucionales y legales, los reparos expresados en ese escrito.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>CUARTO.- LIBRAR, por Secretar\u00eda General, la comunicaci\u00f3n de que trata el art\u00edculo 36 del Decreto 2591 de 1991, para los efectos all\u00ed contemplados. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>C\u00f3piese, notif\u00edquese, comun\u00edquese y c\u00famplase. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ANTONIO JOS\u00c9 LIZARAZO OCAMPO \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>GLORIA STELLA ORTIZ DELGADO \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>PAOLA ANDREA MENESES MOSQUERA \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0<\/p>\n<p>Secretar\u00eda General \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>SALVAMENTO DE VOTO DE LA MAGISTRADA \u00a0<\/p>\n<p>PAOLA ANDREA MENESES MOSQUERA\u00a0 \u00a0<\/p>\n<p>A LA SENTENCIA T-426\/21 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ACCION DE TUTELA CONTRA UNIVERSIDAD-Improcedencia por no cumplir con el requisito de subsidiariedad e inmediatez en proceso disciplinario (Salvamento de voto) \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Expediente: T-8.009.845 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Magistrado ponente:\u00a0 \u00a0<\/p>\n<p>Antonio Jos\u00e9 Lizarazo Ocampo \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Con el acostumbrado respeto por las decisiones de la Sala Cuarta de Revisi\u00f3n de tutelas, suscribo este salvamento de voto en relaci\u00f3n con la sentencia de la referencia. La sentencia de la que me aparto (i) concedi\u00f3 el amparo de los derechos fundamentales al debido proceso y al acceso a la administraci\u00f3n de justicia de la accionante, (ii) dej\u00f3 sin efectos el auto 588, del 20 de junio de 2019, proferido por la Veedur\u00eda Disciplinaria de la Universidad Nacional de Colombia, que rechaz\u00f3 el recurso de apelaci\u00f3n en contra del auto 405 de 8 de mayo de 2019 y (iii) orden\u00f3 a la entidad demandada tramitar y analizar el recurso propuesto con perspectiva de g\u00e9nero, atendiendo a los est\u00e1ndares internacionales, constitucionales y legales en materia de prevenci\u00f3n y sanci\u00f3n de todas las formas de violencia y discriminaci\u00f3n contra las mujeres. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Difiero del an\u00e1lisis y la decisi\u00f3n adoptada en esta providencia, por cuanto considero que no se acredit\u00f3 el cumplimiento de los requisitos de inmediatez y subsidiariedad, por las siguientes razones: \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La acci\u00f3n de tutela no cumple con el requisito de inmediatez. La sentencia sostiene que la demandante present\u00f3 la tutela el 1 de junio de 2020 y la decisi\u00f3n final de rechazo del recurso se dio mediante auto 695 de 23 de julio de 2019, es decir, reconoce que entre la conducta presuntamente violatoria de los derechos fundamentales y la solicitud de amparo transcurrieron once meses. As\u00ed, la decisi\u00f3n considera que, a pesar de que transcurri\u00f3 un lapso superior a seis meses desde que se archiv\u00f3 definitivamente la actuaci\u00f3n, exist\u00edan razones suficientes para justificar la tardanza. En particular, el proyecto refiere que el lapso de once meses era razonable porque \u00aben los casos en los que hay violencia contra la mujer, debe haber una flexibilizaci\u00f3n de los requisitos de procedencia formal de la tutela en aras de no vaciar de contenido el derecho fundamental que se pretende proteger\u00bb. En adici\u00f3n a lo anterior, el proyecto afirma que la pandemia generada por la Covid-19 conllev\u00f3 la suspensi\u00f3n temporal de las labores de los juzgados y la modificaci\u00f3n de las formas de presentar las tutelas, a trav\u00e9s de medios tecnol\u00f3gicos, lo cual impidi\u00f3 el ejercicio oportuno de la acci\u00f3n de tutela. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Si bien comparto dicha aproximaci\u00f3n, pues esta Corte ha flexibilizado los requisitos de procedencia de la acci\u00f3n de tutela, con el prop\u00f3sito de lograr el acceso a una justicia material, considero que dicha flexibilizaci\u00f3n no puede traducirse en el desconocimiento de dichos presupuestos. Trat\u00e1ndose del requisito de inmediatez, en reiterada jurisprudencia, esta Corte ha sostenido que la acci\u00f3n de tutela se puede interponer \u00aben todo momento y lugar\u00bb62, lo que significa que no tiene un t\u00e9rmino de caducidad. No obstante, ha advertido que la solicitud de tutela se debe presentar en un tiempo razonable y proporcionado, a partir del evento generador de la supuesta amenaza o violaci\u00f3n de los derechos fundamentales. Por esta raz\u00f3n, el cumplimiento de este requisito debe verificarse en cada caso.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el asunto sub examine, ni la acci\u00f3n de tutela ni la sentencia dan cuenta de circunstancias que permitan establecer, razonablemente, los motivos por los cuales la accionante tard\u00f3 once meses en presentar la acci\u00f3n de tutela. De hecho, el \u00fanico argumento que plantea el proyecto es que se tiene por cumplido este presupuesto porque se trata de una acci\u00f3n de tutela que pretende, aparentemente, conjurar hechos de violencia contra la accionante, raz\u00f3n por la cual se considera que no se debe aplicar un est\u00e1ndar riguroso para el escrutinio del presupuesto de la inmediatez. Sin embargo, al examinar las circunstancias que motivaron la interposici\u00f3n de la acci\u00f3n de tutela, se advierte que el origen de la controversia es de car\u00e1cter evidentemente legal, pues la conducta presuntamente vulneradora de los derechos fundamentales fue la falta de reconocimiento de la apoderada sustituta que present\u00f3 el recurso de apelaci\u00f3n. Como se puede observar, en estricto sentido, la acci\u00f3n de tutela no se dirige a conjurar los hechos de violencia presuntamente cometidos en contra de la accionante, sino que tiene como objeto controvertir la decisi\u00f3n de archivo de la investigaci\u00f3n, fundada en la indebida representaci\u00f3n de la apoderada sustituta.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En adici\u00f3n a lo anterior, no es de recibo el argumento seg\u00fan el cual la pandemia generada por la Covid-19 supuso un obst\u00e1culo para que la demandante presentara la acci\u00f3n de tutela. Esto, por cuanto, la emergencia generada por la pandemia fue declarada el 17 de marzo de 2020, esto es, nueve meses despu\u00e9s de haberse rechazado el recurso de apelaci\u00f3n. A partir de la informaci\u00f3n obrante en el expediente, no se advierte que, en dicho lapso, la demandante haya adelantado gestiones tendientes a la protecci\u00f3n de los derechos fundamentales presuntamente transgredidos. Lo anterior permite concluir que en este caso no se cumple el requisito de inmediatez, pues no existen razones que permitan justificar la inacci\u00f3n de la demandante para presentar la solicitud de amparo. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La solicitud de amparo no satisface el requisito de subsidiariedad, pues existen medios judiciales ordinarios de defensa para controvertir la decisi\u00f3n de la entidad accionada y no se constat\u00f3 la existencia de un perjuicio irremediable. Esto, en raz\u00f3n a que la controversia planteada se pod\u00eda resolver acudiendo a medios judiciales ordinarios de defensa. En concreto, la accionante dispon\u00eda del medio de control de nulidad y restablecimiento del derecho, regulado por el art\u00edculo 138 de la Ley 1437 de 2011, en el que pod\u00eda aportar todos los elementos necesarios para demostrar que la decisi\u00f3n de archivo, derivada de errores en el poder concedido por la apoderada principal, era contraria a la Constituci\u00f3n y a la ley. Adicionalmente, no hay ninguna circunstancia que permita inferir, as\u00ed sea sumariamente, que la accionante se encuentra ante un perjuicio irremediable, lo que desacredita la procedencia excepcional del amparo. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Fecha ut supra, \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>PAOLA ANDREA MENESES MOSQUERA \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 La Sala Quinta de Revisi\u00f3n conformada por el Acuerdo 4 de 2017 de Sala Plena conserva su competencia para efectos de finalizar el correspondiente proceso, de conformidad con el Par\u00e1grafo transitorio del art\u00edculo 1 del Acuerdo 01 de 2021 de Sala Plena. \u00a0 \u00a0<\/p>\n<p>2 El expediente fue escogido para su revisi\u00f3n por la Sala de Selecci\u00f3n N\u00famero 7, por medio de auto de 15 de diciembre de 2020, notificado el 21 de diciembre de 2021. \u00a0<\/p>\n<p>3 La situaci\u00f3n f\u00e1ctica descrita en esta sentencia se circunscribe a las afirmaciones que cuentan con respaldo probatorio recaudado en las instancias de tutela o en sede de revisi\u00f3n. \u00a0<\/p>\n<p>4 Cuad. 01, f. 30-31. \u00a0<\/p>\n<p>5 Cuad. 01, f. 32-35. \u00a0<\/p>\n<p>6 Cuad. 01, f. 28-29. \u00a0<\/p>\n<p>7 Cuad. 01, f. 38. \u00a0<\/p>\n<p>8 Cuad. 01, f. 38. \u00a0<\/p>\n<p>9 Cuad. 01, f. 38. \u00a0<\/p>\n<p>10 Cuad. 01, f. 38. \u00a0<\/p>\n<p>11 Cuad. 01, f. 39. \u00a0<\/p>\n<p>12 Cuad. 01, f. 39. \u00a0<\/p>\n<p>13 Cuad. 01, f. 39. \u00a0<\/p>\n<p>14 Cuad. 01, f. 45. \u00a0<\/p>\n<p>15 Cuad. 01, f. 46-51. \u00a0<\/p>\n<p>16 Cuad. 01, f. 52-73. \u00a0<\/p>\n<p>17 Cuad. 01, f. 74-75. \u00a0<\/p>\n<p>18 Cuad. 01, f. 82-85. \u00a0<\/p>\n<p>19 Cuad. 01, f. 87. \u00a0<\/p>\n<p>20 Cuad. 01, f. 87. \u00a0<\/p>\n<p>22 Cuad. 01, f. 89. \u00a0<\/p>\n<p>23 Cuad. 01, f. 90. \u00a0<\/p>\n<p>24 Cuad. 01, f. 90. \u00a0<\/p>\n<p>25 Cuad. 01, f. 86-90. \u00a0<\/p>\n<p>26 Cuad. 12. \u00a0<\/p>\n<p>27 Cuad. 13. \u00a0<\/p>\n<p>28 Cuad. 13. \u00a0<\/p>\n<p>29 Cuad. 14. \u00a0<\/p>\n<p>30 Cuad. 19. \u00a0<\/p>\n<p>31 Constituci\u00f3n Pol\u00edtica, art\u00edculo 86; Decreto Ley 2591 de 1991, art\u00edculos 1, 5, 10 y 13. \u00a0<\/p>\n<p>32 Cfr. Al respecto pueden consultarse las Sentencias C-014 de 2004 y T-473 de 2017. \u00a0<\/p>\n<p>33 Sentencia T-718 de 2017. \u00a0<\/p>\n<p>34 \u201cArt\u00edculo XVIII. \u00a0Toda persona puede ocurrir a los tribunales para hacer valer sus derechos. \u00a0Asimismo debe disponer de un procedimiento sencillo y breve por el cual la justicia lo ampare contra actos de la autoridad que violen, en perjuicio suyo, alguno de los derechos fundamentales consagrados constitucionalmente\u201d. \u00a0<\/p>\n<p>35 \u201cArt\u00edculo 8.\u00a0 Garant\u00edas Judiciales. || 1. Toda persona tiene derecho a ser o\u00edda, con las debidas garant\u00edas y dentro de un plazo razonable, por un juez o tribunal competente, independiente e imparcial, establecido con anterioridad por la ley, en la sustanciaci\u00f3n de cualquier acusaci\u00f3n penal formulada contra ella, o para la determinaci\u00f3n de sus derechos y obligaciones de orden civil, laboral, fiscal o de cualquier otro car\u00e1cter. (\u2026)\u201d \u00a0<\/p>\n<p>36 \u201cArt\u00edculo 25.\u00a0 Protecci\u00f3n Judicial. || 1. Toda persona tiene derecho a un recurso sencillo y r\u00e1pido o a cualquier otro recurso efectivo ante los jueces o tribunales competentes, que la ampare contra actos que violen sus derechos fundamentales reconocidos por la Constituci\u00f3n, la ley o la presente Convenci\u00f3n, aun cuando tal violaci\u00f3n sea cometida por personas que act\u00faen en ejercicio de sus funciones oficiales. || 2. Los Estados Partes se comprometen: || \u00a0a) a garantizar que la autoridad competente prevista por el sistema legal del Estado decidir\u00e1 sobre los derechos de toda persona que interponga tal recurso; || b) a desarrollar las posibilidades de recurso judicial, y || c) a garantizar el cumplimiento, por las autoridades competentes, de toda decisi\u00f3n en que se haya estimado procedente el recurso.\u201d \u00a0<\/p>\n<p>37 Comisi\u00f3n Interamericana de Derechos Humanos, Informe de Fondo, N\u00fam. 5\/96,\u00a0Raquel Mart\u00edn de Mej\u00eda\u00a0(Per\u00fa), 1 de marzo de 1996, p\u00e1g. 22. Citado en la sentencia T-772 de 2015. \u00a0<\/p>\n<p>38 Corte Interamericana de Derechos Humanos, Caso Casta\u00f1eda Gutman c. M\u00e9xico. \u00a0<\/p>\n<p>39 Corte Interamericana de Derechos Humanos, Caso Acevedo Jaramillo y otros c. Per\u00fa, Caso L\u00f3pez \u00c1lvarez c. Honduras, Caso Palamara Iribarne c. Chile, y Caso Balde\u00f3n Garc\u00eda c. Per\u00fa. \u00a0<\/p>\n<p>40 Corte Interamericana de Derechos Humanos, Caso Campo Algodonero c. M\u00e9xico. \u00a0<\/p>\n<p>41 Ib\u00eddem.\u00a0 \u00a0<\/p>\n<p>42 Corte Interamericana de Derechos Humanos, Caso Vel\u00e1squez Rodr\u00edguez c Honduras y Caso Fern\u00e1ndez Ortega y otros c. M\u00e9xico. \u00a0<\/p>\n<p>44 \u00a0Comisi\u00f3n Interamericana de Derechos Humanos, informe \u201cAcceso a la justicia para las mujeres v\u00edctimas de violencia en las Am\u00e9ricas\u201d,\u00a020 enero 2007, citado en las sentencias T-012 y T-265 de 2016, y T-027 de 2017. \u00a0<\/p>\n<p>45 Corte Interamericana de Derechos Humanos, Caso Campo Algodonero c. M\u00e9xico. \u00a0<\/p>\n<p>46 Comisi\u00f3n Interamericana de Derechos Humanos, caso de Maria Da Penha c. Brasil. \u00a0<\/p>\n<p>47 Corte Interamericana de Derechos Humanos, Caso Campo Algodonero c. M\u00e9xico. \u00a0<\/p>\n<p>48 Sentencias T-878 de 2014 y T-718 de 2017. Esta postura, a su vez, se relaciona con la reconocimiento de que \u201cla violencia contra la mujer constituye una manifestaci\u00f3n de relaciones de poder hist\u00f3ricamente desiguales entre el hombre y la mujer, que han conducido a la dominaci\u00f3n de la mujer y a la discriminaci\u00f3n en su contra por parte del hombre e impedido el adelanto pleno de la mujer, y que la violencia contra la mujer es uno de los mecanismos sociales fundamentales por los que se fuerza a la mujer a una situaci\u00f3n de subordinaci\u00f3n respecto del hombre\u201d, establecido en la Declaraci\u00f3n sobre la eliminaci\u00f3n de la violencia contra la mujer. \u00a0<\/p>\n<p>49 Sentencia T-878 de 2014. \u00a0<\/p>\n<p>50 Sentencia T-027 de 2017. \u00a0<\/p>\n<p>51 Al respecto, ver las sentencias T-878 y T-967 de 2014, y T-012 de 2016. \u00a0<\/p>\n<p>52 Sentencia T-967 de 2014. \u00a0<\/p>\n<p>53 Sentencia T-145 de 2017. \u00a0<\/p>\n<p>54 En la sentencia T-016 de 2016 se concluy\u00f3 que las agresiones y la discriminaci\u00f3n contra una mujer proven\u00edan no solo de su ex pareja, sino de la administraci\u00f3n de justicia cuando desconoci\u00f3 la gravedad de violencia que sufri\u00f3. \u00a0<\/p>\n<p>55 Ley 1257 de 2008, art\u00edculo 2. \u00a0<\/p>\n<p>56 Ib\u00eddem.\u00a0 \u00a0<\/p>\n<p>57 Declaraci\u00f3n sobre la eliminaci\u00f3n de la violencia contra la mujer, art\u00edculo 2 y Convenci\u00f3n Bel\u00e9m Do Par\u00e1, art\u00edculo 2. \u00a0<\/p>\n<p>58 Cuad. 3, fls. 1-23. \u00a0<\/p>\n<p>59 Sentencia T-264 de 2017. \u00a0<\/p>\n<p>60 Sentencia T-772 de 2015. \u00a0<\/p>\n<p>61 Ib\u00eddem. \u00a0<\/p>\n<p>62 Corte Constitucional. Sentencia SU-961 de 1999. \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia T-426\/21 \u00a0 \u00a0\u00a0 DEBIDO PROCESO DISCIPLINARIO EN ENTORNO UNIVERSITARIO-Vulneraci\u00f3n por demora injustificada en tr\u00e1mite de queja por acoso laboral y sexual\u00a0 \u00a0 \u00a0\u00a0 (La accionada) no cumpli\u00f3 con el t\u00e9rmino razonable, de forma que se aseguraran los derechos fundamentales de la accionante. Por el contrario, se tard\u00f3 m\u00e1s de 3 a\u00f1os analizar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130],"tags":[],"class_list":["post-27660","post","type-post","status-publish","format-standard","hentry","category-tutelas-2020"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/27660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=27660"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/27660\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=27660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=27660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=27660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}