{"id":27668,"date":"2024-07-02T20:38:31","date_gmt":"2024-07-02T20:38:31","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/07\/02\/t-435-20\/"},"modified":"2024-07-02T20:38:31","modified_gmt":"2024-07-02T20:38:31","slug":"t-435-20","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-435-20\/","title":{"rendered":"T-435-20"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia T-435\/20 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DERECHO A LA EDUCACION SUPERIOR DE PERSONAS EN SITUACION DE DISCAPACIDAD-Componente de adaptabilidad \u00a0<\/p>\n<p>DERECHO FUNDAMENTAL A LA EDUCACION DE PERSONAS EN SITUACION DE DISCAPACIDAD-Deber del Estado y de las instituciones de educaci\u00f3n superior para garantizar acceso en condiciones de igualdad \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DERECHO A LA EDUCACION SUPERIOR DE PERSONAS EN SITUACION DE DISCAPACIDAD-Caso en que se solicita el cumplimiento de medidas de acompa\u00f1amiento pedag\u00f3gico dise\u00f1adas por la propia universidad\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>CARENCIA ACTUAL DE OBJETO POR ACAECIMIENTO DE UNA SITUACION SOBREVINIENTE-Estudiante curs\u00f3 y aprob\u00f3 semestre de transici\u00f3n con apoyo de la instituci\u00f3n educativa \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ADAPTABILIDAD COMO COMPONENTE ESENCIAL DEL DERECHO A LA EDUCACION DE PERSONAS EN SITUACION DE DISCAPACIDAD-Obligaci\u00f3n del Estado y las instituciones encargadas de prestar el servicio de educaci\u00f3n frente a las personas con discapacidad \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La Sala considera importante destacar que, si bien estas personas necesitan una serie de ajustes razonables, que sean adecuados a sus necesidades, no por ello puede considerarse que su acceso a la educaci\u00f3n sea menos relevante que el de las dem\u00e1s personas. Quien tiene una discapacidad es un ser humano digno y, por tanto, su educaci\u00f3n debe asumirse con la mayor seriedad y cuidado, tanto por el Estado como por las diversas instituciones p\u00fablicas o privadas a quienes se les conf\u00eda la prestaci\u00f3n del servicio p\u00fablico de educaci\u00f3n. Con los debidos ajustes, propios de la adaptabilidad, una persona con discapacidad puede alcanzar los mismos resultados que las dem\u00e1s, e incluso superiores. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DERECHO A LA EDUCACION SUPERIOR DE PERSONAS EN SITUACION DE DISCAPACIDAD-Orden a instituci\u00f3n superior contin\u00fae brindado apoyos y ajustes que requiera estudiante, a fin de avanzar en su proceso educativo \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Referencia: Expediente T-7.720.117 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Acci\u00f3n de tutela instaurada por Miriam Rivera Osorio, obrando en calidad de agente oficiosa de Catalina Celis Rivera, en contra de la Universidad Tecnol\u00f3gica de Pereira\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Magistrado Sustanciador (E): \u00a0<\/p>\n<p>LUIS JAVIER MORENO ORTIZ \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Bogot\u00e1 D.C., primero (1) de octubre de dos mil veinte (2020) \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La Sala Tercera de Revisi\u00f3n de la Corte Constitucional, integrada por los magistrados Alejandro Linares Cantillo, Antonio Jos\u00e9 Lizarazo Ocampo y Luis Javier Moreno Ortiz, quien la preside, en ejercicio de sus competencias constitucionales y legales, espec\u00edficamente las previstas en los art\u00edculos 86 y 241 numeral 9\u00ba de la Constituci\u00f3n Pol\u00edtica y en el Decreto Ley 2591 de 1991, profiere la siguiente \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>SENTENCIA \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En el tr\u00e1mite de revisi\u00f3n de los fallos de tutela adoptados por el Juzgado Quinto Laboral del Circuito de Pereira y el Tribunal Superior de Pereira, Sala Tercera de Decisi\u00f3n Laboral, dentro de la acci\u00f3n de tutela presentada por la se\u00f1ora Miriam Rivera Osorio, obrando en calidad de agente oficiosa de su hija Catalina Celis Rivera, en contra de la Universidad Tecnol\u00f3gica de Pereira. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>I. \u00a0 \u00a0 \u00a0 \u00a0ANTECEDENTES \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Hechos relevantes1 \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1.1. Catalina Celis Rivera naci\u00f3 el dos de octubre de 1992, es una persona con discapacidad2 y tiene una condici\u00f3n de salud por la que debe consultar, con frecuencia, diferentes especialistas, en ocasiones, con manejo mediante hospitalizaci\u00f3n3.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1.2. En el a\u00f1o 2015, la joven ingres\u00f3 al programa de pregrado de Medicina Veterinaria y Zootecnia en la Universidad Tecnol\u00f3gica de Pereira, en adelante UTP, jornada especial diurna, el cual tiene una duraci\u00f3n de diez semestres. Desde el inicio del programa, ha requerido a la universidad accionada ajustes y apoyos educativos para adelantar sus estudios.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1.3. La se\u00f1ora Miriam Rivera Osorio, en calidad de agente oficiosa de su hija Catalina Celis Rivera, ha promovido dos acciones de tutela anteriores contra la universidad demandada. La primera, que data del a\u00f1o 2015, en la que se ampararon sus derechos a la educaci\u00f3n y a la igualdad, orden\u00e1ndole a la instituci\u00f3n cobrar el valor m\u00ednimo de matr\u00edcula fijado en el Acuerdo No. 0024 del 15 de octubre de 19864. Y, la segunda, ejercida en el a\u00f1o 2016, que protegi\u00f3 su derecho a la educaci\u00f3n inclusiva y, en tal virtud, dispuso a su favor la designaci\u00f3n de \u201cun monitor capacitado en acompa\u00f1amiento de estudiantes en situaci\u00f3n de discapacidad mental\u201d5. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1.4. Como respuesta a la segunda acci\u00f3n constitucional, en mayo de 2016, la UTP se comprometi\u00f3 a brindar acompa\u00f1amiento acad\u00e9mico a la estudiante, por lo que formul\u00f3 la que denomin\u00f3 \u201cPropuesta Acompa\u00f1amiento a Catalina Celis Rivera desde la Universidad Tecnol\u00f3gica de Pereira y la Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario\u201d6, con el objeto de identificar los ajustes o apoyos educativos requeridos y formular el conjunto de acciones a seguir.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1.5. En el marco de esta propuesta, durante los d\u00edas 19, 20 y 21 de octubre de 2016, se le practic\u00f3 a la estudiante una evaluaci\u00f3n neuropsicol\u00f3gica en el Centro de Especialistas de Risaralda -CER-, cuyo informe recomend\u00f3 \u201cque el docente investigue y aprenda acerca de la inteligencia deficiente\u201d, tener cercan\u00eda con la estudiante para conocer sus capacidades y potencialidades a desarrollar, \u201c[u]tilizar im\u00e1genes, fotograf\u00edas u otro material adem\u00e1s de la entrega de instrucciones\u201d, \u201ctrabajar la autoestima, la autodeterminaci\u00f3n, las habilidades sociales y la capacidad de tolerar frustraciones\u201d, \u201cidentificar el estilo de aprendizaje para generar espacios de \u00e9xito acad\u00e9mico, adem\u00e1s de una evaluaci\u00f3n acorde a su diagn\u00f3stico\u201d7.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1.6. La joven Celis Rivera no desempe\u00f1a ning\u00fan trabajo por lo que depende econ\u00f3micamente de su madre8, de quien tambi\u00e9n es beneficiaria en el servicio de salud9. La se\u00f1ora Miriam Rivera Osorio solo cuenta con los ingresos provenientes de una pensi\u00f3n de invalidez que le fue reconocida por la discapacidad de su hija, ya que debi\u00f3 retirarse del trabajo para dedicarse a su cuidado permanente10.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1.7. Catalina Celis Rivera ha estudiado de forma ininterrumpida entre los a\u00f1os 2015 y 2020 durante todos los per\u00edodos lectivos, con la cancelaci\u00f3n del segundo semestre del 2015 y la p\u00e9rdida del primer semestre de 2019. Durante el primero de los per\u00edodos mencionados matricul\u00f3 siete asignaturas del plan de estudios, de las cuales aprob\u00f3 cinco y perdi\u00f3 dos, incluyendo una asignatura intersemestral que tambi\u00e9n super\u00f3. En adelante, matricul\u00f3 por semestre la mitad o menos de las asignaturas exigidas en el plan de estudios como medida personal para avanzar en el programa acad\u00e9mico11, siguiendo la recomendaci\u00f3n de su m\u00e9dico tratante de la E.P.S.12.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1.9. Durante el segundo semestre de 2019, la estudiante curs\u00f3 dos asignaturas y aprob\u00f3 el semestre con promedio de 3.3, superando el estatus de semestre de transici\u00f3n16. Luego, en el primer semestre de 2020, Catalina Celis Rivera curs\u00f3 cuatro asignaturas y aprob\u00f3 el semestre con promedio de 3.817. Y, en el segundo semestre de 2020, esto es, en el actual per\u00edodo lectivo, matricul\u00f3 y se encuentra cursando un total de cinco asignaturas18.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2. \u00a0 \u00a0 \u00a0 \u00a0Presentaci\u00f3n de la acci\u00f3n de tutela \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2.1. El 16 de agosto de 2019, la se\u00f1ora Miriam Rivera Osorio, obrando en calidad de agente oficiosa de su hija Catalina Celis Rivera, promovi\u00f3 acci\u00f3n de tutela contra la UTP, por la presunta vulneraci\u00f3n de los derechos de esta \u00faltima a la dignidad humana, a la igualdad material y a la educaci\u00f3n, como consecuencia de que el citado ente universitario no ha implementado acciones afirmativas que aseguren su continuidad y permanencia en el programa acad\u00e9mico de pregrado de Medicina Veterinaria \u00a0y Zootecnia. Por v\u00eda del referido mecanismo de amparo, la agente oficiosa pretende que el juez constitucional ordene a la entidad accionada, lo siguiente19:\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>i) Ejecutar la propuesta de acompa\u00f1amiento acad\u00e9mico ofrecida por la UTP a la estudiante en el a\u00f1o 2016, en especial, en los componentes que la accionante enuncia como sigue: \u201c5. Brindar formaci\u00f3n y asesor\u00eda, a los docentes del programa acad\u00e9mico de Veterinaria sobre la discapacidad que posee la estudiante, las caracter\u00edsticas propias y estrategias pedag\u00f3gicas para que acceda con mayor facilidad a los nuevos aprendizajes. \/\/ 6. Que al iniciar el semestre acad\u00e9mico, se asigne inmediatamente la monitora permanente de apoyo a estudios, lecturas y trabajos a la estudiante del programa de Medicina Veterinaria y Zootecnia. \/\/ 8. El abordaje adecuado de la discapacidad con la que cuenta la estudiante, haciendo \u00e9nfasis y garantizando un curr\u00edculo y m\u00e9todos de evaluaci\u00f3n diferencial, manejo de horarios y tiempos extendidos para tareas y trabajos, teniendo en cuenta el estilo de aprendizaje, fortalezas de la estudiante y utilizar de (sic) herramientas, recursos, estrategias que le permitan a la estudiante demostrar sus competencias\u201d20.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ii) Revocar o anular la sanci\u00f3n de periodo de prueba y transici\u00f3n por p\u00e9rdida del primer semestre acad\u00e9mico de 2019.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2.2. Como justificaci\u00f3n de ambas pretensiones, refiere a la Ley 1618 de 201321, al Decreto 1421 de 201722 y a la jurisprudencia constitucional en la materia23. En concreto, la accionante expuso que la universidad accionada le exige a su hija una nueva prueba neuropsicol\u00f3gica para adelantar la propuesta de acompa\u00f1amiento acad\u00e9mico, pero no cuenta con recursos econ\u00f3micos para costearla. Adem\u00e1s, la instituci\u00f3n le asigna una monitora, estudiante del pregrado de Medicina Veterinaria y Zootecnia, como apoyo para estudios, lecturas y trabajos, solo por dos horas a la semana, labor que no es permanente y es desempe\u00f1ada por una persona que no est\u00e1 capacitada en acompa\u00f1amiento a estudiantes con discapacidad24.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Particularmente, la accionante asegura que, durante el primer semestre de 2019, la UTP se demor\u00f3 m\u00e1s de dos meses en contratar a la monitora de acompa\u00f1amiento acad\u00e9mico de su hija, lo que deriv\u00f3 en la p\u00e9rdida del periodo lectivo. Por lo dem\u00e1s, impidi\u00f3 la cancelaci\u00f3n del semestre como acci\u00f3n afirmativa diferenciada para garantizar su permanencia educativa, debido a que la p\u00e9rdida del semestre la deja en per\u00edodo de prueba y en semestre de transici\u00f3n, lo que implica el deber de aprobarlo, so pena de que la retiren del programa de pregrado25. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0<\/p>\n<p>3. \u00a0 \u00a0 \u00a0 \u00a0Contestaci\u00f3n de la instituci\u00f3n educativa demandada \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El rector encargado de la UTP solicit\u00f3 negar el amparo. En su criterio, dicha instituci\u00f3n ha realizado todo lo que ha estado a su alcance para llevar a cabo los distintos componentes de la propuesta de acompa\u00f1amiento acad\u00e9mico de la estudiante, pero, por diversas situaciones, ajenas a su voluntad, no ha podido cumplir con todos ellos. Concretamente, se\u00f1al\u00f3 que \u2013tanto la se\u00f1ora Rivera Osorio como su hija\u2013 no han asistido a las citas programadas por la psic\u00f3loga y la fonoaudi\u00f3loga del Programa de Acompa\u00f1amiento Institucional (PAI) y tampoco han aportado pruebas neuropsicol\u00f3gicas actualizadas, que son necesarias, para identificar las necesidades educativas de Catalina Celis Rivera. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Respecto de la sanci\u00f3n de per\u00edodo de prueba o semestre de transici\u00f3n impuesta a la estudiante, por haber perdido el primer semestre lectivo de 2019 con calificaci\u00f3n de 2.0, el rector encargado afirm\u00f3 que la educaci\u00f3n es un derecho-deber, por lo que la promoci\u00f3n y permanencia de la estudiante en el pregrado que cursa depende del cumplimiento de sus obligaciones, pues \u201cel hecho [de] que la estudiante Celis Rivera tenga un tratamiento acad\u00e9mico especial, [el cual] (\u2026) tambi\u00e9n se le aplica (\u2026) [en las evaluaciones], no (\u2026) [conduce a que se pueda] sustraer de la normatividad vigente para todos los estudiantes de la Universidad en cuanto a los procedimientos administrativos\u201d. Adem\u00e1s, \u201c(\u2026) el per\u00edodo de transici\u00f3n es una figura que se aplica a los estudiantes que [,] como es el caso de ella, obtuvieron al terminar el periodo acad\u00e9mico un promedio semestral inferior a dos coma cinco (2.5) (Resoluci\u00f3n 1785\/19)\u201d 26. A esto agrega que, dada la naturaleza p\u00fablica de la UTP, su presupuesto debe extenderse para m\u00e1s de 18.000 estudiantes, 40 de ellos con discapacidad y sin que se le pueda brindar a cada uno un monitor especializado, como s\u00ed lo tiene la estudiante Celis Rivera, a pesar de que algunos de ellos son alumnos \u201ccon mayores discapacidades que [la] accionante\u201d27.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Finalmente, el representante de la accionada asegur\u00f3 que la instituci\u00f3n universitaria no puede dejar de lado sus altas responsabilidades frente a la fe p\u00fablica, cuando certifica las competencias profesionales de quienes terminan un plan de estudios, lo que implica que, en el presente caso, se deban atender tanto los derechos individuales de Catalina Celis Rivera como sus deberes de estudiante. As\u00ed, concluye que la instituci\u00f3n tiene responsabilidades ante la sociedad por la acreditaci\u00f3n de la idoneidad de sus egresados. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>II. DECISIONES OBJETO DE REVISI\u00d3N \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1. \u00a0 \u00a0 \u00a0 \u00a0Sentencia de primera instancia \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En primera instancia, el Juzgado Quinto Laboral del Circuito de Pereira, en sentencia del dos de septiembre de 2019, resolvi\u00f3 negar el amparo deprecado. En relaci\u00f3n con la primera pretensi\u00f3n, referente a que se ordenara ejecutar la propuesta de acompa\u00f1amiento, el juzgado encontr\u00f3 que la universidad accionada demostr\u00f3 haber brindado a la estudiante las herramientas y estrategias necesarias para su desarrollo educativo, ya que, en t\u00e9rminos generales, le hab\u00eda dado cumplimiento a la propuesta realizada, en especial, en lo relativo a los aspectos de realizar un proceso de acercamiento con la estudiante para conocer sus expectativas, autorizaci\u00f3n y aprobaci\u00f3n del proceso; a identificar estilos de aprendizaje y orientar el trabajo pedag\u00f3gico; a efectuar un acompa\u00f1amiento permanente y coparticipativo entre universidad y familia; a brindar formaci\u00f3n y asesor\u00eda a los docentes del programa acad\u00e9mico sobre la discapacidad que posee la estudiante y a asignar un monitor permanente. En cambio, advirti\u00f3 un desinter\u00e9s de la accionante en acudir a las citas y controles de apoyo psicol\u00f3gico y de fonoaudiolog\u00eda ofrecidas por la UTP, lo que originaba consecuencias desfavorables para sus estudios y derivaba en el desconocimiento de su evoluci\u00f3n, con miras, entre otras, a garantizar un plan adecuado de acompa\u00f1amiento.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>A juicio del a quo, la accionante pudo haber promovido el incidente de desacato por la tardanza en la designaci\u00f3n del monitor durante el primer semestre lectivo 2019, ya que la orden espec\u00edfica del monitor fue impartida en tutela anterior por el Tribunal Superior de Pereira &#8211; Sala No. 5 de Asuntos Penales para Adolescentes, correspondi\u00e9ndole al juzgado de primera instancia velar por su cumplimiento. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Frente a la segunda pretensi\u00f3n dirigida a que se ordenara anular la medida sancionatoria del per\u00edodo de transici\u00f3n, por la p\u00e9rdida del primer semestre lectivo 2019, consider\u00f3 que ella hac\u00eda parte del ejercicio de la autonom\u00eda universitaria, sin que existieran motivos que justificaran dar un tratamiento distinto por la sola circunstancia de la discapacidad. Por \u00faltimo, destaca que la accionante tuvo la posibilidad de efectuar la cancelaci\u00f3n de asignaturas o del semestre dentro de los plazos previstos para el efecto, pero no hizo uso de dicha alternativa en el tiempo previsto para ello.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2. \u00a0 \u00a0 \u00a0 \u00a0Impugnaci\u00f3n \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La agente oficiosa impugn\u00f3 la anterior decisi\u00f3n, al considerar que la instituci\u00f3n educativa accionada, a pesar de que no ha cumplido con la propuesta de acompa\u00f1amiento acad\u00e9mico que formul\u00f3 para la estudiante, s\u00ed le aplic\u00f3 la referida medida sancionatoria, con lo cual se amenaza su continuidad en el programa educativo. Sumado a ello, indic\u00f3 que el juez de primera instancia olvid\u00f3 que la autonom\u00eda universitaria tiene l\u00edmites en los derechos fundamentales de las personas que, como su hija, se encuentran con barreras dadas por sus condiciones especiales, de acuerdo con el art\u00edculo 13 superior. \u00a0<\/p>\n<p>3. \u00a0 \u00a0 \u00a0 \u00a0Sentencia de segunda instancia \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En segunda instancia, el Tribunal Superior de Pereira, Sala Tercera de Decisi\u00f3n Laboral, por medio de sentencia proferida el 10 de octubre de 2019, revoc\u00f3 la decisi\u00f3n del a quo para, en su lugar: i) declarar la cosa juzgada constitucional parcial con respecto a la asignaci\u00f3n de un monitor para el acompa\u00f1amiento de la estudiante, pues esta petici\u00f3n ya hab\u00eda sido amparada por el Juzgado Primero Penal del Circuito para Adolescentes de Pereira, en el a\u00f1o 201628; y ii) tutelar los derechos a la educaci\u00f3n inclusiva, a la igualdad y a la dignidad humana de la accionante, para lo cual orden\u00f3 a la UTP redoblar las medidas del Decreto 1421 de 2017, tales como ajuste razonable y curr\u00edculo flexible, con miras a que la estudiante pueda superar el per\u00edodo de transici\u00f3n.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El ad quem no se pronunci\u00f3 con respecto a la primera pretensi\u00f3n, referida a cumplir la propuesta de acompa\u00f1amiento formulada por la UTP en el a\u00f1o 2016, salvo en lo referente a la asignaci\u00f3n del monitor. Frente a la segunda pretensi\u00f3n, a pesar de considerar que el no haber cancelado de manera oportuna del semestre, lo que trajo como consecuencia la sanci\u00f3n consistente en el per\u00edodo de transici\u00f3n, era atribuible a la parte accionante y no a la instituci\u00f3n educativa, consider\u00f3 que la universidad accionada deb\u00eda concurrir en el inter\u00e9s de acompa\u00f1ar los esfuerzos de la estudiante y su familia para continuar con sus estudios, redoblando las medidas de acompa\u00f1amiento integral, para que la estudiante pueda superar dicha condici\u00f3n, en virtud de lo dispuesto en el Decreto 1421 de 2017.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>4. \u00a0 \u00a0 \u00a0 \u00a0Pruebas aportadas al proceso \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Las pruebas aportadas a este proceso, que son documentales, se relacionan enseguida: \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>* Fotocopia de la c\u00e9dula de ciudadan\u00eda de Miriam Rivera Osorio. Folios 42 y 125, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Fotocopia de la c\u00e9dula de ciudadan\u00eda de Catalina Celis Rivera. Folios 43 y 126, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Copia digital de las actuaciones que se adelantaron ante el Juzgado Quinto Civil del Circuito de Pereira, en el tr\u00e1mite de la acci\u00f3n de tutela radicado No. 2015-130, impetrada por la se\u00f1ora Miriam Rivera Osorio contra la Universidad Tecnol\u00f3gica de Pereira. Folio 59, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Copia informal de algunas actuaciones que se adelantaron ante el Juzgado Primero Penal del Circuito para Adolescentes de Pereira en el tr\u00e1mite de la acci\u00f3n de tutela radicado No. 2016-015, impetrada por la se\u00f1ora Rivera Osorio contra la Universidad Tecnol\u00f3gica de Pereira. Folios 171 a 182, cuaderno 1.\u00a0 \u00a0\u00a0<\/p>\n<p>* Documento denominado \u201cPropuesta Acompa\u00f1amiento a Catalina Celis Rivera Desde la Universidad Tecnol\u00f3gica de Pereira y la Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario\u201d. Folios 22, 23, 76 y 77, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Historial acad\u00e9mico de Catalina Celis Rivera en el programa de pregrado de Medicina Veterinaria y Zootecnia. Folios 24, 65 y 66, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Copia informal de comunicaciones electr\u00f3nicas entre la se\u00f1ora Miriam Rivera Osorio y la Universidad Tecnol\u00f3gica de Pereira. Folios 21 a 23, 25 a 33, 35 a 41, 114 y 115, 121 a 124, 129, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Copia informal de comunicaciones electr\u00f3nicas internas de la Universidad Tecnol\u00f3gica de Pereira. Folios 34, 112, 113, 144 a 147, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Captura de pantalla de comunicaciones electr\u00f3nicas entre Catalina Celis Rivera y profesional del PAI. Folios 116 a 120 y 147, 155 a 160, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Captura de pantalla de comunicaciones electr\u00f3nicas entre Miriam Rivera Osorio y profesional del PAI. Folios 148 y 149, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Captura de pantalla de comunicaciones electr\u00f3nicas internas de la Universidad Tecnol\u00f3gica de Pereira. Folios 149 a 154, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Copia informal de dictamen m\u00e9dico laboral practicado a Catalina Celis Rivera el nueve de diciembre de 2013. Folios 44 y 127, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Respuesta negativa a la cancelaci\u00f3n extempor\u00e1nea de semestre acad\u00e9mico emitida por la Universidad Tecnol\u00f3gica de Pereira, con fecha 1\u00b0 de agosto de 2019. Folios 45 y 128, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Certificado No. 7140 expedido por la Directora de admisiones, registro y control acad\u00e9mico de la UTP sobre Catalina Celis Rivera, con fecha 21 de agosto de 2019. Folio 67, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Certificado No. 7290 expedido por la Directora de admisiones, registro y control acad\u00e9mico de la UTP sobre Catalina Celis Rivera, con fecha 23 de agosto de 2019. Folio 168, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Acuerdo No. 05 del 27 de febrero de 2019 \u201c[p]or medio del cual se aprueba el calendario acad\u00e9mico para el primer semestre acad\u00e9mico de 2019\u201d. Folio 169, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Acuerdo No. 04 del 21 de marzo de 2012 \u201c[p]or medio del cual se aclara el plan de estudios del Programa Medicina Veterinaria y Zootecnia\u201d de la Universidad Tecnol\u00f3gica de Pereira. Folios 68 a 74, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Acuerdo No. 37 del 23 de noviembre de 2005 \u201c[p]or medio del cual se reforma el art\u00edculo 48 del estatuto general\u201d de la Universidad Tecnol\u00f3gica de Pereira. Folios 130 y 131, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Acuerdo No. 11 del 17 de junio de 2015 \u201c[p]or medio del cual se establece y reglamenta el sistema institucional de acompa\u00f1amiento acad\u00e9mico\u201d de la Universidad Tecnol\u00f3gica de Pereira. Folios 132 a 134, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Resoluci\u00f3n de rector\u00eda No. 1785 del 03 de abril de 2019 \u201c[p]or medio de la cual se facilita la aplicaci\u00f3n de la reglamentaci\u00f3n vigente del semestre de transici\u00f3n y se dictan otras disposiciones\u201d de la Universidad Tecnol\u00f3gica de Pereira. Folios 135 a 137, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Informe de evaluaci\u00f3n neuropsicol\u00f3gica y resultados prueba WAIS IV practicada a Catalina Celis Rivera los d\u00edas 19, 20 y 21 de octubre de 2016, realizada por especialista del Centro de Especialistas de Risaralda -CER-. Folios 82 a 85, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Informe de seguimiento al caso Catalina Celis Rivera. Folios 102 a 108, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Historia atenci\u00f3n PAI con fecha 21 de agosto de 2019. Folios 139 a 140, cuaderno 1. \u00a0\u00a0<\/p>\n<p>* Listado de estudiantes en situaci\u00f3n de discapacidad matriculados en la UTP durante el 2019-II con indicaci\u00f3n del acompa\u00f1amiento brindado. Folios 141 a 143, cuaderno 1. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>III. REVISI\u00d3N POR LA CORTE CONSTITUCIONAL \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>1. Competencia\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Esta Sala es competente para revisar las decisiones proferidas en la acci\u00f3n de tutela de la referencia, con fundamento en lo previsto en los art\u00edculos 86 y 241.9 de la Constituci\u00f3n Pol\u00edtica, as\u00ed como en virtud del auto del nueve de diciembre de 2019 proferido por la Sala de Selecci\u00f3n de Tutelas N\u00famero Doce, que decidi\u00f3 escoger el expediente de la referencia para su revisi\u00f3n, correspondiendo su estudio a la Sala Tercera de Revisi\u00f3n, presidida por el Magistrado Luis Javier Moreno Ortiz.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2. Actuaciones surtidas en sede de revisi\u00f3n \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2.1. Por medio de Auto del 14 de julio de 2020, la Sala Tercera de Revisi\u00f3n levant\u00f3 la suspensi\u00f3n de t\u00e9rminos dispuesta por el Consejo Superior de la Judicatura en el presente proceso y decret\u00f3 pruebas para verificar los supuestos que dieron lugar a la acci\u00f3n de tutela, a fin de emitir un pronunciamiento de fondo sobre el litigio constitucional suscitado.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2.2. El 17 de julio de 2020, en respuesta al requerimiento de la Sala de Revisi\u00f3n, el Juzgado Primero Penal del Circuito para Adolescentes de Pereira remiti\u00f3 copia simple de las actuaciones surtidas dentro del tr\u00e1mite de tutela radicado No. 2016-015, iniciado por la se\u00f1ora Miriam Rivera Osorio contra la UTP. De acuerdo con el contenido del referido expediente, en dicha oportunidad, si bien se formularon numerosas pretensiones en la demanda dirigidas a que se le ordenara a la instituci\u00f3n educativa demandada brindar el apoyo educativo especializado, y efectuar las adecuaciones curriculares y adaptaciones actitudinales necesarias para garantizar el derecho a la educaci\u00f3n inclusiva de Catalina Celis Rivera, lo cierto fue que solo se tutel\u00f3 lo referente a la designaci\u00f3n de \u201cun monitor capacitado en acompa\u00f1amiento de estudiantes en situaci\u00f3n de discapacidad mental\u201d. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2.3. El 24 de julio de 2020, el Juzgado Quinto Laboral del Circuito de Pereira remiti\u00f3 el despacho comisorio No. 002 del a\u00f1o en cita, mediante el cual alleg\u00f3 material digital contentivo de la declaraci\u00f3n de parte de Catalina Celis Rivera. En la mencionada diligencia, el juzgado comisionado pregunt\u00f3 y la estudiante en forma directa respondi\u00f3 a los interrogantes formulados por esta Corporaci\u00f3n. Las preguntas realizadas y las respuestas obtenidas se resumen a continuaci\u00f3n: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En lo que tiene que ver con la aptitud legal para agenciar sus propios derechos y la capacidad para ser sujeto de derechos y obligaciones, independientemente del uso de apoyos para realizar actos jur\u00eddicos, la estudiante afirm\u00f3 i) decidir y desarrollar de manera independiente actividades propias de su vida cotidiana, sin necesitar el soporte de otra persona, salvo para estudiar, tarea para la cual recibe la ayuda de su madre; ii) escoger sus propias amistades; iii) tener buena comunicaci\u00f3n y relaciones con su n\u00facleo familiar y amigos; iv) no desempe\u00f1ar ning\u00fan trabajo, y v) depender econ\u00f3micamente de su madre. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Con respecto a las condiciones en las que adelanta los estudios superiores, especialmente sobre la continuidad y permanencia en el programa acad\u00e9mico de pregrado de Medicina Veterinaria y Zootecnia de la UTP, la estudiante dijo que inici\u00f3 sus estudios en el a\u00f1o 2015, los cuales ha cursado de manera ininterrumpida y solo ha cancelado el segundo semestre de 2015, porque \u201cno fu[e] capaz con las materias\u201d y eso la afect\u00f3 f\u00edsica y emocionalmente. Sin embargo, decidi\u00f3 continuar. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Entre las razones que aduce para asistir a la universidad se encuentra la motivaci\u00f3n de aprender, de ir a conocer todo lo que tiene que ver con los animales, as\u00ed como poder relacionarse con sus amigos. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Cuando se le pregunt\u00f3 sobre los motivos por los que escogi\u00f3 el programa de Medicina Veterinaria y Zootecnia respondi\u00f3: \u201c(\u2026) desde ni\u00f1a me gust\u00f3 los animales, la biolog\u00eda, y pues los animales han sido parte de mi vida, han sido parte de los que me han ense\u00f1ado lo que es el cari\u00f1o y que a pesar y pues ellos no hablan (\u2026) si (\u2026) pues nosotros dir\u00edamos que no hablan pero ellos hablan con la mirada, con los gestos y quer\u00eda darles (\u2026) eso que ellos me han dado a m\u00ed, quer\u00eda retribu\u00edrselos. Ellos al igual que una persona sienten dolor, sienten tristeza, se enferman, sienten felicidad y quiero ser parte de ese proceso\u201d. Agreg\u00f3 que le encantaba estudiar veterinaria, porque desde ni\u00f1a muchos le dec\u00edan que no lo iba a lograr, que no ser\u00eda capaz y se demostr\u00f3 a s\u00ed misma que sus esfuerzos y los de su familia, sobre todo los de su madre, no son ni han sido p\u00e9rdida de tiempo. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En cuanto a la metodolog\u00eda que emplea para cumplir con las labores acad\u00e9micas, la estudiante afirm\u00f3 que desde ni\u00f1a ha aprendido con el apoyo de su madre al lado, quien le hace todo m\u00e1s l\u00fadico. Adem\u00e1s, consigui\u00f3 una grabadora para grabar las clases, ya que se le facilita el aprendizaje por medios auditivos. Cuando regresa a la casa oye las grabaciones, escribe y vuelve a escribir los contenidos para memorizarlos, despu\u00e9s lee y relee hasta que logra entender. Expuso que acude a internet en busca de material con contenido visual y auditivo, o textos que presenten los contenidos de forma distinta y que le resulten m\u00e1s f\u00e1cilmente comprensibles.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Tambi\u00e9n asegur\u00f3 que cuando no entiende alg\u00fan contenido acad\u00e9mico pide explicaci\u00f3n directa al profesor correspondiente. E indic\u00f3 que, para realizar trabajos o preparar ex\u00e1menes, cuenta con la ayuda de un monitor que es un estudiante de la misma carrera, se apoya en sus compa\u00f1eras de clase e investiga en libros e internet. Se demora entre dos o tres horas estudiando un tema, luego debe repasarlo, por lo cual le pide a su madre que le lea \u201cporque escuchando se [l]e graba m\u00e1s\u201d o que realicen talleres para reforzar lo estudiado. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Con respecto a los apoyos que le ha brindado la UTP para adelantar su proceso educativo, inform\u00f3 que tiene subsidio para el transporte, cuenta con el servicio de psicolog\u00eda disponible para todos los estudiantes de la instituci\u00f3n y se le proporciona un monitor durante todo el semestre de forma constante, aproximadamente dos veces por semana. Se\u00f1ala que este \u00faltimo apoyo, si bien ha contribuido en su proceso formativo, no es suficiente para continuar con sus estudios, ni para entender mejor el programa acad\u00e9mico, ya que tambi\u00e9n es un estudiante que no maneja los temas igual que un profesor29 y dispone de tiempo limitado, pues debe preparar sus propios trabajos y evaluaciones. Afirma que el tiempo que le puede dedicar en ocasiones resulta escaso. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sobre las herramientas pedag\u00f3gicas que demanda una adecuada ense\u00f1anza del pensum acad\u00e9mico, la estudiante expres\u00f3 que, m\u00e1s all\u00e1 del monitor, necesita otras ayudas para poder cursar la carrera y terminarla con \u00e9xito. En concreto, sostuvo que requiere m\u00e1s tiempo para elaborar los trabajos acad\u00e9micos y preparar las evaluaciones. Frente a lo primero, cont\u00f3 la experiencia de un taller manual muy largo, para entrega en tres o cuatro d\u00edas, que no pudo realizar porque se sinti\u00f3 agobiada por el tiempo y el contenido. Frente a lo segundo, consider\u00f3 que le gustar\u00eda rendir las evaluaciones en fechas posteriores a las establecidas para el resto de los estudiantes, ya que no alcanza a prepararlas bien. Asimismo, manifest\u00f3 que, si bien algunos profesores entienden su situaci\u00f3n, no recibe de ellos apoyos diferenciados. Relat\u00f3 que, por motivos de salud, ha faltado a clases y aun llevando excusas m\u00e9dicas es calificada con nota 0.0, por no haber asistido a clase el d\u00eda que era. Esta circunstancia, en particular, le ocurri\u00f3 el semestre anterior. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Finalmente, sobre los motivos por los que obtuvo un bajo promedio de notas en el primer semestre de 2019, la estudiante asegur\u00f3 que curs\u00f3 materias muy pesadas y no comprendi\u00f3 las explicaciones, y que, \u201ca pesar de sus intentos, no fue capaz\u201d.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2.4. El 27 de julio de 2020, el rector y representante legal de la UTP remiti\u00f3 respuesta a los requerimientos de esta Sala de Revisi\u00f3n, en los siguientes t\u00e9rminos. En primer lugar, inform\u00f3 que el centro educativo ha hecho las adaptaciones pertinentes, por medio de la capacitaci\u00f3n a los docentes y la sensibilizaci\u00f3n y flexibilizaci\u00f3n curricular para apoyar a la accionante, quien es, a su juicio, es una estudiante privilegiada, \u201cporque tiene todos los beneficios que la Universidad puede otorgarle a un estudiante\u201d, a saber: reducci\u00f3n del valor de la matr\u00edcula, bono de transporte, asignaci\u00f3n de monitor personal y acompa\u00f1amiento de fonoaudiolog\u00eda y psicolog\u00eda.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Se\u00f1al\u00f3 que el proceso de acompa\u00f1amiento ofrecido por la instituci\u00f3n educativa ha sido trastocado por la inasistencia a citas y asesor\u00edas con las psic\u00f3loga y fonoaudi\u00f3loga del PAI, especialistas en necesidades educativas especiales. De acuerdo con el rector, la estudiante y su madre han tenido una actitud displicente frente a este acompa\u00f1amiento, ya que \u201csolo asistieron a una sesi\u00f3n y no volvieron, por lo que hemos exigido que se actualice la prueba neuropsicol\u00f3gica a efecto de diagnosticar su actual y verdadera situaci\u00f3n, e implementar los procedimientos adecuados, pues se est\u00e1 actuando sobre supuestos diagn\u00f3sticos de hace cuatro o cinco a\u00f1os\u201d. Adem\u00e1s, afirma que no se ha allegado una prueba que demuestre el tratamiento que la estudiante recibe por parte de su E.P.S., ni su diagn\u00f3stico. En su criterio, la estudiante sufre depresi\u00f3n y tiene problemas familiares, siendo estas las principales razones de su falta de \u00e9xito acad\u00e9mico. Por los anteriores motivos, considera que hay temeridad en la interposici\u00f3n de la presente acci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De otra parte, el representante legal afirm\u00f3 que la UTP es \u201cuna Universidad p\u00fablica con m\u00e1s de 18.000 estudiantes y con un presupuesto que debe extenderse para satisfacer las necesidades primordialmente acad\u00e9micas de todos\u201d. Adem\u00e1s, asegur\u00f3 que el tratamiento excepcional dado a la estudiante no es sin\u00f3nimo de generosidad en las calificaciones, ni puede dar lugar a avalar \u201ca una profesional que contradiga su idoneidad\u201d.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Adicionalmente, anex\u00f3 copias del documento titulado \u201cPol\u00edtica institucional de inclusi\u00f3n con enfoque en discapacidad\u201d del a\u00f1o 2020 y del Acuerdo de Consejo Universitario No. 26 del 9 de junio del a\u00f1o en cita, \u201c[p]or medio del cual se adopta la Pol\u00edtica institucional de inclusi\u00f3n con enfoque en discapacidad y se dictan otras disposiciones\u201d, un archivo con informaci\u00f3n y fotograf\u00edas sobre las adaptaciones a la planta f\u00edsica del campus universitario en favor de las personas con discapacidad f\u00edsica y la eliminaci\u00f3n de barreras arquitect\u00f3nicas, y un archivo con la caracterizaci\u00f3n de los estudiantes con discapacidad matriculados en 2020, en los distintos programas acad\u00e9micos ofrecidos por la Universidad.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sobre los apoyos, asistencias, asesor\u00edas y ajustes brindados a la estudiante para facilitar el curso del plan de estudios del programa de Medicina Veterinaria y Zootecnia, la instituci\u00f3n educativa remiti\u00f3 lo siguiente:\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ii) Informe sobre el beneficio bono de transporte, el cual consiste en la entrega de dos tiquetes diarios para el desplazamiento desde el lugar de residencia hasta el campus universitario y viceversa, con el prop\u00f3sito de garantizar la asistencia a clases y apoyar la econom\u00eda familiar con la disminuci\u00f3n de dicho gasto. La estudiante se encuentra exonerada del proceso de corresponsabilidad del servicio social y se ha flexibilizado la regla que exige rendimiento acad\u00e9mico para su otorgamiento, en raz\u00f3n a su discapacidad. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>iii) Dos archivos Excel sobre las monitorias sociales asignadas a la estudiante desde el 2016 hasta el 2020. \u00a0<\/p>\n<p>iv) Informes del monitor social asignado durante el semestre 2020-1 y de profesores del Programa de Medicina Veterinaria y Zootecnia.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La universidad tambi\u00e9n alleg\u00f3 un certificado de la estudiante en el que se\u00f1ala que, al 23 de julio de 2020, \u201ctiene acumulados 108 cr\u00e9ditos acad\u00e9micos y correspondientes al s\u00e9ptimo semestre\u201d y \u201ctiene pendientes veintid\u00f3s (22) asignaturas para culminar su Plan de Estudios\u201d. Y se\u00f1al\u00f3 el link para consultar del reglamento estudiantil actualizado. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por \u00faltimo, el rector sugiri\u00f3 \u201cdisponer la recepci\u00f3n de una actualizada prueba neuropsicol\u00f3gica o un examen que permita establecer la real situaci\u00f3n de discapacidad de la accionante\u201d y solicitar a la EPS informar \u201csi ha adelantado o en la actualidad est\u00e1 adelantando tratamiento alguno a la estudiante Celis Rivera\u201d. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>2.5. Posteriormente, en Auto del 12 de agosto de 2020, la Sala Tercera de Revisi\u00f3n solicit\u00f3 a la Universidad Tecnol\u00f3gica de Pereira enviar los certificados de calificaciones de la estudiante correspondientes al segundo semestre de 2019 y al primer semestre de 2020, as\u00ed como un certificado de asignaturas que hab\u00edan sido matriculadas para el segundo semestre de este a\u00f1o. Tambi\u00e9n pidi\u00f3 informar sobre el acompa\u00f1amiento acad\u00e9mico brindado durante el per\u00edodo lectivo 2019-02 y las medidas adoptadas por la universidad para dar cumplimiento a la orden de amparo impartida en segunda instancia, por el Tribunal Superior de Pereira, Sala Tercera de Decisi\u00f3n Laboral, por medio de sentencia proferida el 10 de octubre de 2019, correspondiente a la segunda tutela que fue presentada. El 21 de agosto de 2020. La UTP dio respuesta al mencionado auto y remiti\u00f3 las certificaciones e informe solicitados.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>3. Presentaci\u00f3n del caso y planteamiento de los problemas jur\u00eddicos \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>3.1. La se\u00f1ora Miriam Rivera Osorio, obrando en calidad de agente oficiosa de su hija Catalina Celis Rivera, interpuso la presente acci\u00f3n de tutela en contra de la Universidad Tecnol\u00f3gico de Pereira (UTP) por la presunta vulneraci\u00f3n de los derechos fundamentales de esta \u00faltima a la dignidad humana, a la educaci\u00f3n y a la igualdad material, por la falta de implementaci\u00f3n de acciones afirmativas que garanticen su continuidad y permanencia en el pregrado que cursa.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La agente oficiosa pretende que el juez constitucional ordene a la universidad accionada: i) dar cumplimiento a la propuesta de acompa\u00f1amiento acad\u00e9mico formulada por la Universidad, en el 2016, especialmente en cuanto a \u201c5. Brindar formaci\u00f3n y asesor\u00eda, a los docentes del programa acad\u00e9mico de Veterinaria sobre la discapacidad que posee la estudiante, las caracter\u00edsticas propias y estrategias pedag\u00f3gicas para que acceda con mayor facilidad a los nuevos aprendizajes. \/\/ 6. Que al iniciar el semestre acad\u00e9mico, se asigne inmediatamente la monitora permanente de apoyo a estudios, lecturas y trabajos a la estudiante del programa de Medicina Veterinaria y Zootecnia. \/\/ 8. el abordaje adecuado de la discapacidad con la que cuenta la estudiante, haciendo \u00e9nfasis y garantizando un curr\u00edculo y m\u00e9todos de evaluaci\u00f3n diferencial, manejo de horarios y tiempos extendidos para tareas y trabajos, teniendo en cuenta el estilo de aprendizaje, fortalezas de la estudiante y utilizar de (sic) herramientas, recursos, estrategias que le permitan a la estudiante demostrar sus competencias\u201d; y ii) revocar o anular la sanci\u00f3n de per\u00edodo de prueba y transici\u00f3n por p\u00e9rdida del primer semestre acad\u00e9mico de 2019, ya que pone a la estudiante en riesgo de quedar por fuera del programa definitivamente. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>3.2. El representante legal de la UTP solicita denegar el amparo deprecado, pues sostiene que la universidad ha desplegado todo lo que ha estado a su alcance para llevar a cabo los distintos componentes de la propuesta de acompa\u00f1amiento acad\u00e9mico a la estudiante, pero, por diversas situaciones, ajenas a su voluntad, no ha podido dar cumplimiento a todos ellos. En concreto, se\u00f1al\u00f3 que la agente oficiosa y la estudiante no han asistido a las citas programadas por la psic\u00f3loga y la fonoaudi\u00f3loga del Programa de Acompa\u00f1amiento Institucional (PAI) y tampoco han aportado pruebas neuropsicol\u00f3gicas actualizadas que permitan valorar las capacidades e identificar las necesidades educativas de Catalina Celis Rivera. Adem\u00e1s, no se cuenta con un diagn\u00f3stico m\u00e9dico de \u201cla supuesta discapacidad de la estudiante\u201d. Por los anteriores motivos, considera que hay temeridad en la interposici\u00f3n de la presente acci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El rector de la instituci\u00f3n educativa se opone a cada una de las pretensiones de la demanda, argumentando la imposibilidad de brindar a la estudiante, i) un tratamiento acad\u00e9mico distinto al del resto de estudiantes del pregrado de veterinaria, ya que esto comportar\u00eda una vulneraci\u00f3n del derecho a la igualdad y afectar\u00eda la obligaci\u00f3n de la universidad de garantizar la idoneidad profesional de la egresada; ii) un tratamiento administrativo distinto al del resto de los estudiantes de la universidad, puesto que su \u201csituaci\u00f3n de discapacidad\u201d no implica una justificaci\u00f3n para eximirla del cumplimiento de sus deberes acad\u00e9micos o excusarla por no promover oportunamente los tr\u00e1mites dispuestos para la cancelaci\u00f3n de semestre; iii) un apoyo pedag\u00f3gico especializado dada la limitada cantidad de recursos econ\u00f3micos disponibles dentro del presupuesto institucional y la imperiosa necesidad de distribuirlos entre los cerca de 18.000 estudiantes matriculados en la instituci\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>3.3. A partir de las circunstancias que dieron lugar al ejercicio de la acci\u00f3n de tutela, de las pruebas recaudadas y de las decisiones adoptadas en las respectivas instancias judiciales, esta Sala de Revisi\u00f3n:\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Cuesti\u00f3n previa: A modo de cuesti\u00f3n previa, debe determinarse si existe temeridad y si se ha configurado el fen\u00f3meno de la cosa juzgada constitucional en el presente asunto, considerando que esta es la tercera vez que la accionante interpone una acci\u00f3n constitucional de amparo en contra de la universidad accionada.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Primer problema jur\u00eddico: En caso de superarse lo anterior, debe establecerse si se cumplen los requisitos de procedencia de la acci\u00f3n de tutela, en particular, en lo que respecta a la legitimaci\u00f3n en la causa por activa, ya que la acci\u00f3n de tutela se present\u00f3 por la se\u00f1ora Miriam Rivera Osorio, como agente oficiosa de su hija Catalina Celis Rivera, persona mayor de edad con discapacidad.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Segundo problema jur\u00eddico. De ser procedente la tutela, debe valorarse la circunstancia de que, seg\u00fan la informaci\u00f3n dada por la UTP en sede de revisi\u00f3n, la accionante super\u00f3 el semestre de transici\u00f3n que curs\u00f3 en el segundo periodo lectivo de 2019, y posteriormente curs\u00f3 y aprob\u00f3 el primer semestre y est\u00e1 cursando el segundo semestre de 2020, de cara a una posible carencia actual de objeto, en cuanto ata\u00f1e a la pretensi\u00f3n relativa a esta materia. \u00a0<\/p>\n<p>Tercer problema jur\u00eddico. Por \u00faltimo, respecto de la pretensi\u00f3n restante, debe verificar si la UTP vulner\u00f3 los derechos a la dignidad humana, a la igualdad material y a la educaci\u00f3n de Catalina Celis Rivera, quien manifiesta ser una persona con discapacidad, al no haber dado cumplimiento a algunos componentes de la propuesta de acompa\u00f1amiento acad\u00e9mico formulada para la estudiante, por la propia universidad, en el a\u00f1o 2016, valga decir, si la UTP ha desconocido el derecho de una estudiante con discapacidad a permanecer en el sistema educativo, a partir de la obligaci\u00f3n de las instituciones de educaci\u00f3n superior de realizar ajustes razonables adecuados a sus necesidades.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>4. Soluci\u00f3n a la cuesti\u00f3n previa: no existe temeridad y s\u00f3lo se configura respecto de un elemento de la primera pretensi\u00f3n el fen\u00f3meno de la cosa juzgada constitucional \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>4.1. El art\u00edculo 38 del Decreto 2591 de 1991 estableci\u00f3 la figura de la temeridad para precaver afectaciones a la administraci\u00f3n de justicia en materia de acci\u00f3n de tutela, cuyo funcionamiento se ver\u00eda perjudicado si una persona, sin una justificaci\u00f3n razonable, elevase la misma causa ante los jueces de la Rep\u00fablica, contra las mismas partes y buscando la satisfacci\u00f3n de id\u00e9nticas pretensiones, Al respecto, la norma en cita expresamente se\u00f1ala que:\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cArt\u00edculo 38. Actuaci\u00f3n temeraria. Cuando, sin motivo expresamente justificado, la misma acci\u00f3n de tutela sea presentada por la misma persona o su representante ante varios jueces o tribunales, se rechazar\u00e1 o decidir\u00e1 desfavorablemente todas las solicitudes. \/\/ El abogado que promoviere la presentaci\u00f3n de varias acciones de tutela respecto de los mismos hechos y derechos, ser\u00e1 sancionado con la suspensi\u00f3n de la tarjeta profesional al menos por dos a\u00f1os. En caso de reincidencia, se le cancelar\u00e1 su tarjeta profesional, sin perjuicio de las dem\u00e1s sanciones a que haya lugar.\u201d \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En la Sentencia C-054 de 1993, la Corte declar\u00f3 la exequibilidad de esta norma y se\u00f1al\u00f3 que \u201ccon base en los art\u00edculos 83, 95 y 209 de la Constituci\u00f3n, la actuaci\u00f3n temeraria debe ser controlada en aras de lograr la efectividad y agilidad en el funcionamiento del Estado\u201d. Para esta Corporaci\u00f3n \u201cel [uso] desmedido e irracional del recurso judicial (\u2026) ocasiona un perjuicio para toda la sociedad, porque (\u2026) la repetici\u00f3n de casos id\u00e9nticos necesariamente implica una p\u00e9rdida directamente proporcional en la capacidad judicial del Estado para atender los requerimientos del resto de [ciudadanos]\u201d30. Por ello, la sanci\u00f3n procesal por efectuar esa conducta, esto es, rechazar o decidir desfavorablemente todas las solicitudes, se ha considerado ajustada al ordenamiento superior, dado que incide positivamente tanto en la efectividad del recurso de amparo como en la celeridad de la Administraci\u00f3n de Justicia31. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>4.2. Como se infiere de la norma previamente transcrita, para que exista una actuaci\u00f3n temeraria es necesario que concurran tres elementos: identidad de causa, identidad de partes e identidad de pretensiones o de objeto. En la Sentencia T-727 de 2011, esta Corporaci\u00f3n se\u00f1al\u00f3 que existe temeridad cuando se presenta: \u201c(i) una identidad en el objeto, es decir, que \u2018las demandas busquen la satisfacci\u00f3n de una misma pretensi\u00f3n tutelar o sobre todo el amparo de un mismo derecho fundamental\u201932; (ii) una identidad de causa petendi, que hace referencia a \u2018que el ejercicio de las acciones se fundamente en unos mismos hechos que le sirvan de causa\u201933; y, (iii) una identidad de partes, o sea que las acciones de tutela se hayan dirigido contra el mismo demandado y, del mismo modo, se hayan interpuesto por el mismo demandante, ya sea en su condici\u00f3n de persona natural o persona jur\u00eddica, de manera directa o por medio de apoderado34\u201d.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Con todo, la sola concurrencia de tales elementos no conlleva al surgimiento autom\u00e1tico de la temeridad que, como ya se dijo, tiene por consecuencia la exclusi\u00f3n de un nuevo pronunciamiento tutelar. As\u00ed, siguiendo lo establecido en el art\u00edculo 38 del Decreto 2591 de 1991, a pesar de la identidad de causa, objeto y pretensiones, el accionante debe de carecer de un motivo justificado y expreso para incoar de nuevo la acci\u00f3n constitucional. Al respecto, en la Sentencia T-919 de 2003, este tribunal apunt\u00f3 que: \u201c[c]uando en un proceso aparezca como factible la declaraci\u00f3n de improcedencia en virtud de una posible identidad de partes, hechos y pretensiones, el juez tiene el deber de verificar que tal posibilidad en efecto se configure en el caso concreto y adicionalmente que no existe una causa razonable para hacer uso nuevamente de la acci\u00f3n, en el caso de que efectivamente se presente la identidad (\u2026)\u201d. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por esta raz\u00f3n y atendiendo a la presunci\u00f3n de buena fe que ampara los actos de los particulares, puede declararse la ocurrencia de una temeridad, luego de que el juez constitucional examine con cuidado las circunstancias que envuelven el caso en concreto y establezca que la actuaci\u00f3n, entre otras, \u201c(i) resulta ama\u00f1ada, en la medida en que el actor se reserva para cada demanda los argumentos o pruebas que convalidan sus pretensiones; (ii) denote el prop\u00f3sito desleal de obtener la satisfacci\u00f3n del inter\u00e9s individual a toda costa, jugando con la eventualidad de una interpretaci\u00f3n judicial que, entre varias, pudiera resultar favorable; (iii) deje al descubierto el \u2018abuso del derecho porque [de forma delibera] y sin tener raz\u00f3n, de mala fe se instaura la acci\u00f3n; o finalmente (iv) pretenda[,] a trav\u00e9s de personas inescrupulosas[,] asaltar la buena fe de los administradores de justicia\u201d35. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Y como reiteradamente lo ha expuesto esta Corporaci\u00f3n36, una vez se acredita la existencia de una actuaci\u00f3n temeraria, adem\u00e1s de declarar la improcedencia de la acci\u00f3n, en los t\u00e9rminos del art\u00edculo 38 del Decreto 2591 de 1991, el juez de tutela puede imponer la sanci\u00f3n pecuniaria prevista en los art\u00edculos 80 y 81 del C\u00f3digo General del Proceso a quien incurre en dicho comportamiento, salvo que \u201cel ejercicio de las acciones de tutela se [haya] funda[do] (i) en la ignorancia del accionante; (ii) en el asesoramiento errado de los profesionales del derecho; o (iii) por el sometimiento del actor a un estado de indefensi\u00f3n, propio de aquellas situaciones en que los individuos obran por miedo insuperable o por la necesidad extrema de defender un derecho. En estos casos, si bien lo que se impone es declarar la improcedencia de las acciones de tutela indebidamente interpuestas como lo dispone la ley, no es viable la imposici\u00f3n de sanci\u00f3n alguna en contra de quien incurre en dicha conducta, b\u00e1sicamente por la inexistencia de un supuesto que permita acreditar que se actu\u00f3 de mala fe\u201d37. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En suma, cuando quiera que una persona acuda ante el juez constitucional para que \u00e9ste resuelva una causa exacta, busque la satisfacci\u00f3n de id\u00e9nticas pretensiones y demande a la misma parte, salvo que exista un motivo expreso y razonable, deber\u00e1 declararse la improcedencia de la acci\u00f3n de tutela, sin perjuicio del examen sobre la ignorancia, el asesoramiento errado o el estado de indefensi\u00f3n, caso en el cual se excluir\u00eda la posibilidad de imponer las sanciones pecuniarias previstas en el C\u00f3digo General del Proceso.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>4.3. El conjunto de reglas expuestas no solo se aplica para aquellos casos en que se presenta un ejercicio simult\u00e1neo de dos o m\u00e1s acciones de tutela, sino tambi\u00e9n cuando su formulaci\u00f3n ocurre de forma sucesiva, esto es, cuando a la interposici\u00f3n de una nueva solicitud le antecede otra que ya ha sido resuelta por las autoridades judiciales. En esta \u00faltima hip\u00f3tesis, en la que una misma persona instaura sucesivamente varias acciones de amparo en las que converge la triple identidad (partes, hechos y pretensiones), este tribunal ha precisado que, m\u00e1s all\u00e1 de la declaratoria de temeridad, es preciso estudiar si ha operado el fen\u00f3meno de la cosa juzgada constitucional sobre la primera de las acciones promovidas, ya que, cuando ello ocurre, por sustracci\u00f3n de materia, las tutelas subsiguientes son improcedentes38. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Para tal efecto, como se expuso en la Sentencia SU-1219 de 2001, por regla general, cuando el juez de tutela resuelve un asunto en concreto y posteriormente la Corte Constitucional decide sobre su selecci\u00f3n, la decisi\u00f3n judicial sobre el caso se torna definitiva, inmutable y vinculante39. Si la Corte, en ejercicio de su competencia constitucional de revisi\u00f3n, decide seleccionar el caso para su estudio, la cosa juzgada constitucional se produce con la ejecutoria del fallo de la propia Corte y, cuando no lo selecciona, la misma opera a partir de la ejecutoria del auto en que se decide la no selecci\u00f3n. Luego de ello, la decisi\u00f3n queda ejecutoriada desde el punto de vista formal y material, por lo que no es posible que se profiera un nuevo pronunciamiento sobre el mismo asunto40, a menos que se est\u00e9 ante fen\u00f3menos como el de la cosa juzgada fraudulenta41, pues ello desconocer\u00eda la seguridad jur\u00eddica que brinda esta herramienta de cierre del sistema jur\u00eddico. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De este modo, se concluye que las instituciones de la cosa juzgada y la temeridad pretenden evitar la presentaci\u00f3n sucesiva y simult\u00e1nea de las acciones de tutela. Aun cuando son conceptos diferentes, existen hip\u00f3tesis en las que confluyen. As\u00ed, por ejemplo, \u00fanicamente se presenta la temeridad cuando se incurre en la presentaci\u00f3n simult\u00e1nea de dos o m\u00e1s solicitudes que presentan la triple identidad a la que se ha aludido, sin motivo que lo justifique y sin que ninguna haya hecho tr\u00e1nsito a cosa juzgada. Por el contrario, existe cosa juzgada y temeridad cuando se interpone una acci\u00f3n de amparo sobre una causa decidida previamente en otro proceso de igual naturaleza, sin que existan razones que justifiquen la nueva solicitud. En este \u00faltimo caso, solo habr\u00e1 lugar a la imposici\u00f3n de una sanci\u00f3n, como se explic\u00f3, cuando se acredite que el actuar de quien incurri\u00f3 en dicha conducta es contrario a los postulados de la buena fe.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>4.4. En el asunto sub examine, la se\u00f1ora Miriam Rivera Osorio, obrando en calidad de agente oficiosa de su hija Catalina Celis Rivera, interpuso acci\u00f3n de tutela en contra de la Universidad Tecnol\u00f3gica de Pereira (UTP), por la presunta vulneraci\u00f3n de los derechos fundamentales de esta \u00faltima a la dignidad humana, a la educaci\u00f3n y a la igualdad material. Con este mecanismo, la agente oficiosa pretende que el juez constitucional ordene a la instituci\u00f3n educativa accionada: i) ejecutar la propuesta de acompa\u00f1amiento acad\u00e9mico ofrecida a la estudiante desde el a\u00f1o 2016, en especial los componentes referentes a: \u201c5. Brindar formaci\u00f3n y asesor\u00eda, a los docentes del programa acad\u00e9mico de Veterinaria sobre la discapacidad que posee la estudiante, las caracter\u00edsticas propias y estrategias pedag\u00f3gicas para que acceda con mayor facilidad a los nuevos aprendizajes. \/\/ 6. Que al iniciar el semestre acad\u00e9mico, se asigne inmediatamente la monitora permanente de apoyo a estudios, lecturas y trabajos a la estudiante del programa de Medicina Veterinaria y Zootecnia. \/\/ 8. el abordaje adecuado de la discapacidad con la que cuenta la estudiante, haciendo \u00e9nfasis y garantizando un curr\u00edculo y m\u00e9todos de evaluaci\u00f3n diferencial, manejo de horarios y tiempos extendidos para tareas y trabajos, teniendo en cuenta el estilo de aprendizaje, fortalezas de la estudiante y utilizar de (sic) herramientas, recursos, estrategias que le permitan a la estudiante demostrar sus competencias\u201d; y ii) revocar o anular la sanci\u00f3n de periodo de prueba y transici\u00f3n por p\u00e9rdida del primer semestre de 2019. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Frente a las necesidades educativas de su hija Catalina Celis Rivera, la agente oficiosa ha promovido dos acciones de tutela anteriores contra la universidad demandada. Una primera ante el Juzgado Quinto Civil del Circuito de Pereira, en primera instancia, en la que se invoc\u00f3 el amparo de los derechos fundamentales a \u201cla vida integral, educaci\u00f3n inclusiva e integridad, debido proceso, m\u00ednimo vital, y el derecho a la igualdad\u201d, en la que solicit\u00f3 que se i) le cobre el costo m\u00ednimo de matr\u00edcula establecido por la universidad; ii) se reliquide ese valor desde el primer semestre; iii) se hagan adecuaciones curriculares, por ejemplo, para la preparaci\u00f3n y presentaci\u00f3n de evaluaciones; iv) se le suministre durante toda la carrera los bonos de transporte y alimentaci\u00f3n; v) se le otorgue un monitor y v) se le garantice su derecho a la intimidad, consistente en no comentar sus problemas de salud con sus compa\u00f1eros, a fin de no ser discriminada.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En sentencia del 14 de mayo de 2015, el juzgado de instancia concedi\u00f3 el amparo de los derechos a la educaci\u00f3n y a la igualdad y orden\u00f3 a la UTP cobrarle a la estudiante Celis Rivera el valor m\u00ednimo de matr\u00edcula establecido en el Acuerdo n\u00famero 0024 del 15 de octubre de 1986. Sin embargo, no accedi\u00f3 al resto de solicitudes con base en los siguientes argumentos: i) con sujeci\u00f3n a los efectos de los actos jur\u00eddicos, no cab\u00eda ordenar una reliquidaci\u00f3n de lo pagado de forma retroactiva; ii) las adecuaciones curriculares deb\u00edan formularse a la instituci\u00f3n universitaria, iii) el otorgamiento de bonos de transporte y alimentaci\u00f3n requieren un estudio socioecon\u00f3mico que evidencie la situaci\u00f3n particular y real de la estudiante y su familia; y, iv) en cuanto a la garant\u00eda de intimidad, el alegato era carente de precisi\u00f3n. Esta decisi\u00f3n se confirm\u00f3 por el Tribunal Superior de Pereira, Sala Civil Familia, en segunda instancia, en fallo del 3 de julio de 2015. El expediente se identific\u00f3 en la Corte con el n\u00famero de radicaci\u00f3n T-5.165.758, el cual no fue seleccionado para revisi\u00f3n en el Auto de 15 de octubre de 201542.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En un segundo recurso promovido ante el Juzgado Primero Penal del Circuito para Adolescentes de Pereira, en primera instancia, se invoc\u00f3 el amparo de los derechos fundamentales a \u201cla vida integral, educaci\u00f3n inclusiva e integridad, debido proceso, m\u00ednimo vital, y el derecho a la igualdad [y] equidad\u201d. La accionante solicit\u00f3 para su hija que la UTP: i) le brinde el apoyo pedag\u00f3gico especializado individual y pertinente para su aprendizaje, como estudiante con discapacidad y con necesidades educativas especiales, incluyendo la adecuaci\u00f3n y flexibilizaci\u00f3n del curr\u00edculo, el plan de estudios y los procesos de evaluaci\u00f3n de acuerdo con sus diagn\u00f3sticos cl\u00ednicos; ii) que se hagan las adecuaciones curriculares; iii) que se utilicen metodolog\u00edas apropiadas para su aprendizaje, dirigidas a potencializar sus capacidades, habilidades y mejorar su rendimiento acad\u00e9mico; iv) que se involucre a los docentes que orientan las materias y tutores para que brinden una orientaci\u00f3n pedag\u00f3gica adecuada a la estudiante con discapacidad intelectual; v) que se establezcan variaciones a las pruebas de evaluaci\u00f3n; y vi) que se eliminen las barreras y obst\u00e1culos que le impiden permanecer y culminar sus estudios.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por medio de fallo del 23 de febrero de 2016, el juzgado de instancia neg\u00f3 el amparo solicitado, al considerar que la universidad demandada s\u00ed le hab\u00eda brindado a la estudiante los apoyos requeridos, en aras de garantizar su permanencia y mejor desempe\u00f1o acad\u00e9mico y no estaba obligada a dise\u00f1ar un curr\u00edculo exclusivo, pues ello atentar\u00eda contra el principio de autonom\u00eda universitaria. Esta decisi\u00f3n fue revocada por el Tribunal Superior de Pereira, Sala No. 5 de Asuntos Penales para Adolescentes, en sentencia del 11 de abril de 2016, que encontr\u00f3 que se hab\u00eda incumplido el compromiso de la Universidad de garantizar a la estudiante un monitor capacitado, por lo que ampar\u00f3 el derecho fundamental a la educaci\u00f3n inclusiva y, en tal virtud, dispuso a su favor la designaci\u00f3n de \u201cun monitor capacitado en acompa\u00f1amiento de estudiantes en situaci\u00f3n de discapacidad mental\u201d43. El expediente fue identificado en la Corte con el n\u00famero de radicaci\u00f3n T-5.651.354, el cual fue excluido de revisi\u00f3n por parte de esta Corporaci\u00f3n en auto de 28 de julio de 201644.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Producto de esta segunda tutela, la UTP se comprometi\u00f3 en mayo de 2016, a brindar acompa\u00f1amiento acad\u00e9mico a la estudiante. Por ello, formul\u00f3 la \u201cPropuesta Acompa\u00f1amiento a Catalina Celis Rivera desde la Universidad Tecnol\u00f3gica de Pereira y la Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario\u201d, cuyo cumplimiento parcial se demanda en este proceso. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>Vistos los hechos que fundamentan el caso, es claro que se est\u00e1 en presencia de un ejercicio sucesivo de la acci\u00f3n de tutela, respecto de una materia que guarda conexidad tem\u00e1tica. As\u00ed, pues, debe determinarse si se configura o no el fen\u00f3meno de la cosa juzgada constitucional, a partir de las decisiones anteriormente proferidas. Desde esta perspectiva, se entrar\u00e1 a examinar si existe la triple identidad (partes, causa y objeto) y, de ser as\u00ed, por sustracci\u00f3n de materia, como ya se explic\u00f3, declarar la improcedencia de la acci\u00f3n objeto de revisi\u00f3n.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En cuanto a las partes, este Tribunal estima que existe coincidencia material en los sujetos que integran los roles activo y pasivo de los tres procesos. Ello es as\u00ed, por cuanto, en las tres oportunidades, la Universidad Tecnol\u00f3gica de Pereira fue demandada por la se\u00f1ora Miriam Rivera Osorio, obrando en calidad de agente oficiosa de su hija Catalina Celis Rivera.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En lo que respecta al objeto, es preciso se\u00f1alar que si bien en las tres acciones de tutela se formularon pretensiones dirigidas a que se ordene a la instituci\u00f3n la implementaci\u00f3n de acciones afirmativas que garanticen la continuidad y permanencia de la estudiante en el programa acad\u00e9mico de pregrado de Medicina Veterinaria y Zootecnia, solo en esta oportunidad se hace referencia concreta al cumplimiento de algunos componentes espec\u00edficos de la propuesta rese\u00f1ada con anterioridad, ofrecida por la propia universidad a la estudiante desde el mes de mayo de 2016. Como ya se ha dicho: a) en la primera acci\u00f3n de tutela junto a pretensiones de distinta naturaleza se solicit\u00f3 ordenar el cobro del valor m\u00ednimo de matr\u00edcula establecido por la universidad, \u00fanica pretensi\u00f3n a la que accedi\u00f3 el juez constitucional; b) en el segundo recurso de amparo, pese a las numerosas pretensiones, solo se orden\u00f3 la designaci\u00f3n de \u201cun monitor capacitado en acompa\u00f1amiento de estudiantes en situaci\u00f3n de discapacidad mental\u201d; y c) en la tutela objeto de revisi\u00f3n se pide, i) adem\u00e1s de satisfacer lo prometido en la propuesta de acompa\u00f1amiento de 2016, incluyendo la asignaci\u00f3n inmediata de la monitora permanente de apoyo, que se proceda a ii) revocar o anular la sanci\u00f3n de per\u00edodo de prueba y transici\u00f3n por p\u00e9rdida del primer semestre acad\u00e9mico de 2019. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>As\u00ed las cosas, la identidad de objeto se aprecia, a primera vista, en relaci\u00f3n con uno de los elementos de la primera de las pretensiones de este proceso: \u201c6. Que[,] al iniciar el semestre acad\u00e9mico, se asigne inmediatamente la monitora permanente de apoyo a estudios, lecturas y trabajos\u201d, ya que esta solicitud fue resuelta en la segunda acci\u00f3n de tutela y la accionante cuenta con la posibilidad de tramitar el incidente de desacato. Queda por examinar si frente a los dem\u00e1s elementos de la primera pretensi\u00f3n y a la segunda pretensi\u00f3n se presenta identidad de causa. Con respecto a este punto, se encuentra que los hechos sobre los que se pronunci\u00f3 el juez constitucional en las tres acciones de tutela son distintos.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En la primera tutela, la balanza se inclin\u00f3 en favor de la protecci\u00f3n del derecho a la educaci\u00f3n inclusiva de la accionante, al garantizar su continuidad desde la perspectiva material, por su precaria situaci\u00f3n econ\u00f3mica. En la segunda tutela, la protecci\u00f3n del derecho a la educaci\u00f3n inclusiva se concret\u00f3 en disponer el acompa\u00f1amiento pedag\u00f3gico, a trav\u00e9s de un monitor personal capacitado en el manejo de estudiantes en situaci\u00f3n de discapacidad, no solo porque hab\u00eda sido un ofrecimiento de la propia universidad sino tambi\u00e9n porque tal apoyo resultaba indispensable para que la estudiante pudiese avanzar en su proceso formativo. En contraste con lo anterior, en la presente acci\u00f3n se busca que la UTP i) de cumplimiento a la propuesta de acompa\u00f1amiento acad\u00e9mico por ella formulada, en el a\u00f1o 2016, especialmente, en cuanto a: \u201c5. Brindar formaci\u00f3n y asesor\u00eda, a los docentes del programa acad\u00e9mico de Veterinaria sobre la discapacidad que posee la estudiante, las caracter\u00edsticas propias y estrategias pedag\u00f3gicas para que acceda con mayor facilidad a los nuevos aprendizajes. \/\/ 8. el abordaje adecuado de la discapacidad con la que cuenta la estudiante, haciendo \u00e9nfasis y garantizando un curr\u00edculo y m\u00e9todos de evaluaci\u00f3n diferencial, manejo de horarios y tiempos extendidos para tareas y trabajos, teniendo en cuenta el estilo de aprendizaje, fortalezas de la estudiante y utilizar de (sic) herramientas, recursos, estrategias que le permitan a la estudiante demostrar sus competencias\u201d; y, adem\u00e1s de lo anterior, en que se ii) revoque o anule la sanci\u00f3n de per\u00edodo de prueba y transici\u00f3n por p\u00e9rdida del primer semestre acad\u00e9mico de 2019. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En este contexto, a diferencia de las dos tutelas anteriores, en esta \u00faltima se busca i) el cumplimiento de medidas de acompa\u00f1amiento pedag\u00f3gico dise\u00f1adas por la propia universidad, a fin de lograr la inclusi\u00f3n educativa de la estudiante, luego de cinco a\u00f1os de estar cursando el plan de estudios; ii) as\u00ed como la flexibilizaci\u00f3n de medidas administrativas y acad\u00e9micas que posibiliten su permanencia y continuidad en el pregrado escogido. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En suma, una vez realizado un examen integral de las tres actuaciones judiciales adelantadas en sede de tutela, esta Sala de Revisi\u00f3n encuentra que solo se acredita la triple identidad, en cuanto ata\u00f1e a un elemento de la primera pretensi\u00f3n: \u201c6. Que[,] al iniciar el semestre acad\u00e9mico, se asigne inmediatamente la monitora permanente de apoyo a estudios, lecturas y trabajos a la estudiante del programa de Medicina Veterinaria y Zootecnia\u201d. Por lo tanto, en lo que a este elemento respecta, se confirmar\u00e1 la decisi\u00f3n de segunda instancia, en la cual se declar\u00f3 la existencia de cosa juzgada constitucional. No se impondr\u00e1 sanci\u00f3n alguna a la accionante, por considerar que en su actuar no se vislumbra mala fe. Esta consideraci\u00f3n se funda en el mandato del art\u00edculo 83 de la Carta, conforme al cual se presume la buena fe en estas gestiones, y en la circunstancia de que no hay elementos de juicio suficientes para desvirtuar dicha pretensi\u00f3n, ya que la conducta se produce en un contexto dado \u201cpor el sometimiento del actor a un estado de indefensi\u00f3n, propio de aquellas situaciones en que los individuos obran (&#8230;) por la necesidad extrema de defender un derecho\u201d 45, considerando que su actual solicitud se fund\u00f3 en las que considera son las necesidades educativas espec\u00edficas de su hija, a fin de continuar y culminar sus estudios superiores, sin negar la existencia de las tutelas ya decididas. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>5. Soluci\u00f3n al primer problema jur\u00eddico: la acci\u00f3n de tutela cumple todos los requisitos de procedencia \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>5.1. Legitimaci\u00f3n en la causa por activa \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica reconoce el derecho de toda persona a reclamar mediante acci\u00f3n de tutela la protecci\u00f3n inmediata de sus derechos fundamentales. Este precepto se desarrolla en el art\u00edculo 10 del Decreto 2591 de 1991, en el que se establece que: \u201cla acci\u00f3n de tutela podr\u00e1 ser ejercida, en todo momento y lugar, por cualquiera persona vulnerada o amenazada en uno de sus derechos fundamentales, quien actuar\u00e1 por s\u00ed misma o a trav\u00e9s de representante. Los poderes se presumir\u00e1n aut\u00e9nticos. Tambi\u00e9n se pueden agenciar derechos ajenos cuando el titular de los mismos no est\u00e9 en condiciones de promover su propia defensa. Cuando tal circunstancia ocurra, deber\u00e1 manifestarse en la solicitud\u201d.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En el caso bajo examen, se observa que, en principio, se cumple con el requisito de legitimaci\u00f3n en la causa por activa, toda vez que la se\u00f1ora Miriam Rivera Osorio i) manifest\u00f3 expresamente que presenta la acci\u00f3n de tutela en calidad de agente oficiosa de su hija Catalina Celis Rivera, se\u00f1alando, adem\u00e1s, ii) que lo hace por su discapacidad f\u00edsica e intelectual respaldada en diagn\u00f3sticos m\u00e9dicos.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>No obstante, el hecho de tener una discapacidad \u2013incluso si es de car\u00e1cter intelectual o psicosocial\u2013 no constituye una raz\u00f3n que, por s\u00ed sola, justifique la agencia oficiosa en materia de la tutela, por virtud de la aplicaci\u00f3n del principio de igual reconocimiento previsto en el art\u00edculo 12 de la Convenci\u00f3n sobre los Derechos de las Personas con Discapacidad -CDPCD-46, de conformidad con el cual resulta imperativo que el juez constitucional interprete la figura, buscando favorecer la capacidad jur\u00eddica de las personas mayores de edad en situaci\u00f3n de discapacidad, con el fin de preservar su autonom\u00eda y voluntad. Particularmente, en la Sentencia T-072 de 201947, al examinar la agencia oficiosa de los padres frente a sus hijos mayores de edad en situaci\u00f3n de discapacidad, la Corte sostuvo:\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cCon todo, a partir del principio de igual reconocimiento ante la ley, resulta imperativo que el juez constitucional interprete la figura de la agencia oficiosa buscando favorecer la capacidad jur\u00eddica de las personas mayores de edad en condici\u00f3n de discapacidad, a efectos de preservar su autonom\u00eda y voluntad. Para tal efecto, en lo que respecta al requisito de la imposibilidad de interponer el recurso de amparo, se deber\u00e1 entrar a analizar las circunstancias del caso concreto y las barreras de participaci\u00f3n efectiva en la sociedad que se derivan para el titular de los derechos, sin que el solo diagn\u00f3stico de una enfermedad intelectual o psicosocial, sea un indicio suficiente para derivar el impedimento en una actuaci\u00f3n directa. En otras palabras, el juez constitucional debe velar porque existan escenarios en los que las personas con discapacidad, en virtud de su capacidad jur\u00eddica, se apropien de sus derechos y de la facultad para proceder a su ejercicio, con miras a fortalecer su independencia e inclusi\u00f3n en la vida social\u201d. \u00a0<\/p>\n<p>Vale decir que, en la actualidad, este principio se encuentra desarrollado en la Ley 1996 de 2019, que establece \u201cel r\u00e9gimen para el ejercicio de la capacidad legal de las personas con discapacidad mayores de edad\u201d. En ella se dispone la presunci\u00f3n de capacidad, en los siguientes t\u00e9rminos: \u201c[t]odas las personas con discapacidad son sujetos de derecho y obligaciones, y tienen capacidad legal en igualdad de condiciones, sin distinci\u00f3n alguna e independientemente de si usan o no apoyos para la realizaci\u00f3n de actos jur\u00eddicos. \/\/ En ning\u00fan caso la existencia de una discapacidad podr\u00e1 ser motivo para la restricci\u00f3n de la capacidad de ejercicio de una persona (&#8230;)\u201d (art. 6\u00ba). \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En el presente caso, la estudiante es una persona mayor de edad (28 a\u00f1os), estudiante de un programa acad\u00e9mico de educaci\u00f3n superior que, al parecer, est\u00e1 siendo afectada en sus derechos fundamentales por parte de la universidad accionada. La solicitud se formula, precisamente, ante las dificultades de aprendizaje de la estudiante, quien requiere de una constante repetici\u00f3n (auditiva y visual) para memorizar y comprender los conceptos, de un tiempo adicional para realizar trabajos y preparar ex\u00e1menes, del apoyo de tutores personales y de materiales did\u00e1cticos que faciliten la exposici\u00f3n de los contenidos, lo que ha derivado en que despu\u00e9s de cinco a\u00f1os continuos de estudios, a diferencia de sus compa\u00f1eros de clase, no haya completado el pensum acad\u00e9mico, pues debe matricular la mitad de las asignaturas del semestre para poder cursarlas y, en algunos casos, ha tenido que repetirlas hasta aprobarlas.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>A pesar de estas barreras, en declaraci\u00f3n de parte comisionada por este tribunal, la joven Celis Rivera afirm\u00f3 que es capaz de decidir y desarrollar de manera independiente actividades propias de su vida cotidiana, sin necesitar el soporte de otra persona, salvo para estudiar. Por ello, al menos en principio, podr\u00eda concluirse que la tutela es improcedente, ya que la referida joven est\u00e1 en condiciones de acudir al amparo constitucional directamente y sin el apoyo de nadie. No obstante, en la misma diligencia, la estudiante ratific\u00f3 los hechos y pretensiones de la demanda y aclar\u00f3 que la decisi\u00f3n de interponerla se debi\u00f3 a una valoraci\u00f3n conjunta con su madre. Textualmente, dijo que: \u201cLas dos hablamos, y las dos pensamos que era lo mejor (..) Yo le pido ayuda a mi mam\u00e1, pues yo le dije y ella me dio la opci\u00f3n y yo le dije que era buena idea\u201d. De ah\u00ed que se entiende plenamente satisfecho este requisito de procedencia, puesto que se acredita la autonom\u00eda y voluntad de Catalina Celis Rivera en la promoci\u00f3n de la tutela bajo revisi\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Este tribunal debe llamar la atenci\u00f3n de los jueces de instancia, en la medida en que ninguno de ellos estudi\u00f3, con el debido detenimiento, la agencia oficiosa, pese a tratarse de una situaci\u00f3n procesal puesta de presente por la persona que present\u00f3 la tutela en nombre de su hija mayor de edad. Y tambi\u00e9n debe hacerlo, porque ninguno de los jueces de instancia tuvo la preocupaci\u00f3n de preguntar a la agenciada si convalidaba o ratificaba la actuaci\u00f3n. Fue necesario que este tribunal decretara la pr\u00e1ctica de unas pruebas y comisionara a los jueces del lugar, para que se pudiera saber que la titular de los derechos fundamentales, que es una persona mayor de edad con discapacidad, ratifica la actuaci\u00f3n de su madre, que obr\u00f3 como agente oficiosa. En vista de lo anterior, la prueba practicada no deja margen de duda sobre la ratificaci\u00f3n de lo actuado por la agente oficiosa y, por tanto, sobre la legitimidad en la causa por activa. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>5.2. Legitimaci\u00f3n en la causa por pasiva \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>El referido art\u00edculo 86 del Texto Superior establece que la acci\u00f3n de tutela tiene por objeto la protecci\u00f3n efectiva e inmediata de los derechos fundamentales, cuando quiera que estos resulten vulnerados o amenazados por la acci\u00f3n u omisi\u00f3n de las autoridades p\u00fablicas o de los particulares, en los casos previstos en la Constituci\u00f3n y en la ley. Este tribunal ha dicho, de manera reiterada, que para satisfacer el requisito de legitimaci\u00f3n en la causa por pasiva es necesario acreditar dos requisitos: i) que se trate de uno de los sujetos respecto de los cuales procede el amparo; y ii) que la conducta que genera la vulneraci\u00f3n o amenaza del derecho se pueda vincular, directa o indirectamente, con su acci\u00f3n u omisi\u00f3n48.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En el asunto bajo examen est\u00e1 acreditado este requisito de procedencia. De una parte, el accionado es una entidad p\u00fablica y, adem\u00e1s, presta un servicio p\u00fablico. En efecto, la UTP es un establecimiento educativo de car\u00e1cter p\u00fablico, con r\u00e9gimen especial, creado por la Ley 41 de 1958, con personer\u00eda jur\u00eddica, autonom\u00eda administrativa, financiera, acad\u00e9mica y patrimonio independiente, adscrita al Ministerio de Educaci\u00f3n. De otra parte, la conducta a la que se atribuye la vulneraci\u00f3n de derechos fundamentales, consistente a negar un trato distinto que garantice a la accionante su inclusi\u00f3n educativa y posibilite su continuidad y permanencia en el programa acad\u00e9mico de pregrado que cursa, puede vincularse directamente a la UTP. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>5.3. Inmediatez \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>La acci\u00f3n de tutela tambi\u00e9n exige que su interposici\u00f3n se lleve a cabo dentro de un plazo razonable, contabilizado a partir del momento en el que se gener\u00f3 la vulneraci\u00f3n o amenaza del derecho fundamental, de manera que el amparo responda a la exigencia constitucional de ser un instrumento judicial de aplicaci\u00f3n inmediata y urgente (C.P. art. 86), con miras a asegurar la efectividad concreta y actual del derecho objeto de violaci\u00f3n o amenaza. Este requisito ha sido identificado por la jurisprudencia como el principio de inmediatez.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Respecto de los elementos que subsisten de la primera pretensi\u00f3n, para establecer la inmediatez, es necesario considerar dos factores: i) el de que dicha pretensi\u00f3n busca que se cumpla con diversos aspectos de la propuesta de acompa\u00f1amiento acad\u00e9mico, hecha por la UTP en 2016, cuya ejecuci\u00f3n es de car\u00e1cter permanente, esto es, durante el transcurso del programa educativo; y ii) el de que al momento de presentar la tutela la estudiante todav\u00eda estaba adelantando dicho programa. Al tratarse de un proceso educativo en curso, en el cual las dificultades de la estudiante con discapacidad permanecen y las ayudas y acompa\u00f1amiento debe darse en cada semestre, al considerarse que ello no ocurri\u00f3 as\u00ed durante el primer semestre de 2019, la accionante present\u00f3 la tutela sub examine el 16 de agosto de 2019, es decir, poco m\u00e1s de un mes despu\u00e9s de la terminaci\u00f3n del mismo, dado que el \u00faltimo d\u00eda de clases fue el 13 de julio de 2019.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Respecto de la segunda pretensi\u00f3n, se tiene que la sanci\u00f3n acad\u00e9mica, generada por la p\u00e9rdida ocurrida en el primer semestre de 2019, ser\u00eda aplicable en el segundo semestre de ese a\u00f1o. En esta medida, la tutela se presenta antes de que la amenaza a los derechos fundamentales se concrete y, en todo caso, se llega a ella luego de haberse solicitado a la UPT la cancelaci\u00f3n del semestre49 y de haberse recibido la respuesta negativa de dicha instituci\u00f3n50. Entre la definici\u00f3n de este asunto por la accionada y la presentaci\u00f3n de la tutela, hay apenas 15 d\u00edas. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por lo anterior, se considera que se cumple con el requisito de inmediatez en relaci\u00f3n con la oportunidad en la presentaci\u00f3n de la tutela objeto de estudio. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>5.4. Subsidiariedad \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Finalmente, el art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica se\u00f1ala que la acci\u00f3n de amparo solo proceder\u00e1 cuando el afectado no disponga de otro medio de defensa judicial, salvo que se utilice como mecanismo transitorio para evitar un perjuicio irremediable51. Esto significa que la tutela tiene un car\u00e1cter residual o subsidiario que obedece a la necesidad de preservar el reparto de competencias atribuido por la Constituci\u00f3n Pol\u00edtica y la ley a las diferentes autoridades judiciales, lo cual se sustenta en los principios de independencia y autonom\u00eda de la actividad jurisdiccional.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>No obstante, aun existiendo otros mecanismos de defensa judicial, este tribunal ha admitido que la acci\u00f3n de tutela est\u00e1 llamada a prosperar, cuando se acredita que los mismos no son lo suficientemente id\u00f3neos para otorgar un amparo integral, o no son lo suficientemente expeditos para evitar la ocurrencia de un perjuicio irremediable. As\u00ed lo sostuvo en la Sentencia SU-961 de 1999, al considerar que: \u201cen cada caso, el juez est\u00e1 en la obligaci\u00f3n de determinar si las acciones disponibles le otorgan una protecci\u00f3n eficaz y completa a quien la interpone. Si no es as\u00ed, si los mecanismos ordinarios carecen de tales caracter\u00edsticas, el juez puede otorgar el amparo de dos maneras distintas, dependiendo de la situaci\u00f3n de que se trate. La primera posibilidad es que las acciones ordinarias sean lo suficientemente amplias para proveer un remedio integral, pero que no sean lo suficientemente expeditas para evitar el acontecimiento de un perjuicio irremediable. En este caso ser\u00e1 procedente la acci\u00f3n de tutela como mecanismo transitorio, mientras se resuelve el caso a trav\u00e9s de la v\u00eda ordinaria\u201d. La segunda posibilidad es que las acciones comunes no sean susceptibles de resolver el problema de forma id\u00f3nea, circunstancia en la cual es procedente conceder la tutela de manera directa, como mecanismo de protecci\u00f3n definitiva de los derechos fundamentales52.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Respecto de este \u00faltimo punto, este tribunal ha entendido que el mecanismo ordinario previsto por el ordenamiento jur\u00eddico para resolver un asunto no es id\u00f3neo, cuando, por ejemplo, no permite resolver el conflicto en su dimensi\u00f3n constitucional o no ofrece una soluci\u00f3n integral frente al derecho supuestamente comprometido. En este sentido, esta Corporaci\u00f3n ha dicho que: \u201cel requisito de la idoneidad ha sido interpretado por la Corte a la luz del principio seg\u00fan el cual el juez de tutela debe dar prioridad a la realizaci\u00f3n de los derechos sobre las consideraciones de \u00edndole formal53. La aptitud del medio de defensa ordinario debe ser analizada en cada caso concreto, teniendo en cuenta, las caracter\u00edsticas procesales del mecanismo, las circunstancias del peticionario y el derecho fundamental involucrado\u201d54. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Ahora bien, en relaci\u00f3n con las controversias suscitadas en torno a la continuidad del derecho a la educaci\u00f3n, la doctrina de este tribunal ha se\u00f1alado que, en principio, ellas deben ser tramitadas ante la jurisdicci\u00f3n ordinaria o contenciosa administrativa, dependiendo del tipo de establecimiento que brinde la oferta educativa55. No obstante, cuando se encuentre comprometida la continuidad del proceso educativo, es necesario evaluar la eficacia e idoneidad en concreto del medio judicial, ante el car\u00e1cter urgente y la necesidad de evitar la interrupci\u00f3n en la prestaci\u00f3n del servicio. Al respecto, se ha dicho que:\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cEn diferentes oportunidades la jurisprudencia constitucional ha se\u00f1alado que el principio de continuidad garantiza la efectiva prestaci\u00f3n y la permanencia del servicio p\u00fablico de educaci\u00f3n, de tal modo que, las interrupciones que excepcionalmente se presenten deben estar debidamente justificadas. En este sentido, es claro que cualquier tipo de controversia que se genere en desarrollo de la prestaci\u00f3n del servicio, y que afecte su continuidad, repercute directamente en el ejercicio del derecho fundamental a la educaci\u00f3n, de tal modo que, atendiendo a las causales de procedencia excepcional de la acci\u00f3n de tutela se\u00f1aladas anteriormente, la misma puede usarse con la finalidad de preservar la continuidad del proceso formativo. Tal procedencia puede darse, seg\u00fan las circunstancias del caso, de manera definitiva o transitoriamente mientras el asunto se decide en la v\u00eda ordinaria\u201d56. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Con fundamento en lo anterior, que en este caso se acredita el cumplimiento del requisito de subsidiariedad, por las siguientes razones: i) frente a la pretensi\u00f3n de dar cumplimiento a algunos componentes de la \u201cPropuesta Acompa\u00f1amiento a [la se\u00f1ora] Catalina Celis Rivera desde la Universidad Tecnol\u00f3gica de Pereira y la Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario\u201d, la accionante no cuenta con la posibilidad de acudir ante la jurisdicci\u00f3n de lo contencioso administrativo, ya que dicho documento, en estricto sentido, no es un acto administrativo que pueda ser ejecutable; adem\u00e1s, no tiene otro mecanismo judicial de defensa id\u00f3neo, distinto al amparo, que le permita reclamar la protecci\u00f3n de su derecho a la educaci\u00f3n; ii) frente a la pretensi\u00f3n de eliminar o anular la sanci\u00f3n acad\u00e9mica impuesta por la p\u00e9rdida del primer semestre de 2019, ella no se concreta en un acto administrativo que pueda ser cuestionado en el marco de un proceso contencioso; si bien podr\u00eda plantearse la posibilidad de controvertir la decisi\u00f3n negativa de la universidad a la solicitud de cancelaci\u00f3n del semestre acad\u00e9mico perdido ante la jurisdicci\u00f3n de lo contencioso-administrativo, a trav\u00e9s de la acci\u00f3n de nulidad y restablecimiento del derecho contemplada en el art\u00edculo 138 del CPACA57, el ejercicio de la acci\u00f3n de tutela en este caso persigue una finalidad constitucional: la continuidad y permanencia de una estudiante con discapacidad en el sistema de educaci\u00f3n superior, que excede la supuesta ilegalidad de un aparente acto administrativo, y que no se encuadra dentro de las causales de procedencia de dicho medio de control, como lo son, que el acto hubiese sido expedido \u201ccon infracci\u00f3n de las normas en que deber\u00edan fundarse, o sin competencia, o en forma irregular, o con desconocimiento del derecho de audiencia y defensa, o mediante falsa motivaci\u00f3n, o con desviaci\u00f3n de las atribuciones propias de quien los profiri\u00f3\u201d58. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>6. Soluci\u00f3n al segundo problema jur\u00eddico: se configura la carencia actual de objeto respecto de la segunda pretensi\u00f3n, pero no respecto de la primera \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>6.1. En algunas ocasiones las circunstancias que dieron origen a la presunta vulneraci\u00f3n de derechos pueden resultar alteradas o desaparecer, lo que conlleva a que la acci\u00f3n de tutela pierda su sustento o raz\u00f3n de ser como mecanismo extraordinario de protecci\u00f3n judicial. Estos casos han sido agrupados por la doctrina constitucional bajo el concepto de \u201ccarencia actual de objeto\u201d que, inicialmente, solo contempl\u00f3 dos categor\u00edas, a saber: hecho superado y da\u00f1o consumado. El hecho sobreviniente es un tercer tipo de categor\u00eda, m\u00e1s reciente y m\u00e1s amplia, dise\u00f1ada para cubrir escenarios que no encajan en las categor\u00edas originales cuyo com\u00fan denominador es la ocurrencia de una nueva circunstancia que, con posterioridad a la presentaci\u00f3n de la tutela, hace que pierda efecto el posible amparo59. Sobre la causal gen\u00e9rica de carencia de objeto denominada hecho sobreviniente y las hip\u00f3tesis que se pueden enmarcar dentro de esta, en el Sentencia SU-522 de 2019, este tribunal precis\u00f3:\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201cEl hecho sobreviniente ha sido reconocido tanto por la Sala Plena como por las distintas Salas de Revisi\u00f3n. Es una categor\u00eda que ha demostrado ser de gran utilidad para el concepto de carencia actual de objeto, pues por su amplitud cobija casos que no se enmarcan en los conceptos tradicionales de da\u00f1o consumado y hecho superado. El hecho sobreviniente remite a cualquier \u201cotra circunstancia que determine que, igualmente, la orden del juez de tutela relativa a lo solicitado en la demanda de amparo no surta ning\u00fan efecto y por lo tanto caiga en el vac\u00edo\u201d. No se trata entonces de una categor\u00eda homog\u00e9nea y completamente delimitada. A manera de ilustraci\u00f3n, la jurisprudencia ha declarado un hecho sobreviniente cuando: (i) el actor mismo es quien asume la carga que no le correspond\u00eda para superar la situaci\u00f3n vulneradora; (ii) un tercero \u2013distinto al accionante y a la entidad demandada- ha logrado que la pretensi\u00f3n de la tutela se satisfaga en lo fundamental; (iii) es imposible proferir alguna orden por razones que no son atribuibles a la entidad demandada; o (iv) el actor simplemente pierde inter\u00e9s en el objeto original de la litis.\u201d \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>6.2. En el presente caso, en cuanto ata\u00f1e a la segunda pretensi\u00f3n de la tutela, referida a anular o cancelar la sanci\u00f3n acad\u00e9mica de per\u00edodo en transici\u00f3n, impuesta a la estudiante por la p\u00e9rdida del primer semestre de 2019, la Sala encuentra que se presenta en la actualidad una carencia de objeto por hecho sobreviniente, por las razones que se explican a continuaci\u00f3n.\u00a0 \u00a0<\/p>\n<p>Si bien podr\u00eda considerarse que la actuaci\u00f3n de la universidad accionada, al negar la solicitud de cancelaci\u00f3n del primer semestre de 2019 e imponer la sanci\u00f3n acad\u00e9mica de semestre de transici\u00f3n durante el segundo semestre de 2019, no tuvo en cuenta la situaci\u00f3n de vulnerabilidad de la accionante y, en consecuencia, pudo haber desconocido los derechos fundamentales a la educaci\u00f3n y a la igualdad de las personas con discapacidad, por no haber adoptado los ajustes administrativos y acad\u00e9micos oportunos y adecuados para garantizar la \u00a0permanencia de la joven universitaria en el sistema educativo, lo relevante del caso es que la estudiante asumi\u00f3 una carga que, en principio, no le correspond\u00eda -curs\u00f3 el semestre de transici\u00f3n- y super\u00f3 la situaci\u00f3n vulneradora -aprob\u00f3 el semestre de transici\u00f3n- con el apoyo de la instituci\u00f3n educativa, en cumplimiento de la orden impartida por el juez de segunda instancia.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En efecto, seg\u00fan informa la UTP en el tr\u00e1mite de este proceso, la estudiante aprob\u00f3 el referido per\u00edodo \u201cgracias al empe\u00f1o y dedicaci\u00f3n de los docentes del Programa que tuvieron a cargo las asignaturas; al equipo del PAI (Programa de Acompa\u00f1amiento Integral) de la Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario; de los monitores que han estado exclusiva y permanentemente en el acompa\u00f1amiento acad\u00e9mico; de la fonoaudi\u00f3loga que la ha atendido y, del personal administrativo que ha estado pendiente de los requerimientos no tanto de la estudiante sino [especialmente] de su progenitora\u201d60. Esto se comprueba con la certificaci\u00f3n remitida por la universidad, en la que consta que, durante el segundo semestre de 2019, la estudiante curs\u00f3 dos asignaturas y aprob\u00f3 el semestre con promedio de 3.3, superando el estatus de semestre de transici\u00f3n61. A los muchos m\u00e9ritos que reconoce la UPT a diferentes personas, la Sala considera necesario agregar, los de la accionante, pues sin su esfuerzo acad\u00e9mico el resultado no habr\u00eda sido posible.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Al haberse superado de manera exitosa el per\u00edodo de transici\u00f3n, en la actualidad no existe ya riesgo alguno para la estudiante de quedar por fuera del programa acad\u00e9mico. De acuerdo con la Resoluci\u00f3n de rector\u00eda No. 1785 del 03 de abril de 2019 de la UTP, \u201c[p]or medio de la cual se facilita la aplicaci\u00f3n de la reglamentaci\u00f3n vigente del semestre de transici\u00f3n y se dictan otras disposiciones\u201d62, son causales para quedar por fuera del programa por un semestre: \u201c1. Obtener un promedio semestral inferior a tres coma cero (3,0) en el semestre de transici\u00f3n\u201d y, en este caso, la estudiante obtuvo una calificaci\u00f3n de 3.3, que supera la condici\u00f3n exigida. Adem\u00e1s, con posterioridad a la superaci\u00f3n del semestre de transici\u00f3n -segundo semestre de 2019-, en el primer semestre de 2020, Catalina Celis Rivera curs\u00f3 cuatro asignaturas y aprob\u00f3 el semestre con promedio de 3.863. Y, para el segundo semestre de 2020, matricul\u00f3 y se encuentra cursando cinco asignaturas64.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En suma, al cambiar la situaci\u00f3n de hecho que motiv\u00f3 la presentaci\u00f3n de la demanda, el amparo se torna de imposible realizaci\u00f3n, por cuanto se presenta una carencia actual de objeto, en la medida en que resulta innecesario pronunciarse sobre los derechos invocados por la accionante y ya no tiene sentido proferir \u00f3rdenes de protecci\u00f3n. En consecuencia, en la parte resolutiva de esta decisi\u00f3n, se revocar\u00e1 el fallo de segunda instancia que ampar\u00f3 los derechos de la accionante, en lo que ata\u00f1e a la pretensi\u00f3n de anular o cancelar la sanci\u00f3n acad\u00e9mica de per\u00edodo en transici\u00f3n y, en su lugar, se declarar\u00e1 la carencia actual de objeto por el acaecimiento de hechos sobrevinientes. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Respecto de la primera pretensi\u00f3n de la tutela, por el contrario, la situaci\u00f3n es diferente, ya que la necesidad de cumplir con la propuesta de la UTP se mantiene, en la medida en que la estudiante sigue cursando su carrera universitaria.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7. Soluci\u00f3n al tercer problema jur\u00eddico: no se advierte la vulneraci\u00f3n de los derechos fundamentales de la accionante, pero es necesario mantener las medidas propuestas por la UPT \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por razones metodol\u00f3gicas, antes de resolver este problema jur\u00eddico, la Sala dar\u00e1 cuenta, a modo de par\u00e1metro, de los dos elementos constitucionales relevantes: el componente de adaptabilidad en el \u00e1mbito de la educaci\u00f3n superior y los deberes del Estado y de las instituciones de educaci\u00f3n superior frente a la educaci\u00f3n de las personas con discapacidad. Sobre esta base analizar\u00e1 el caso concreto y adoptar\u00e1 una decisi\u00f3n. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.1. El derecho a la educaci\u00f3n y el componente de adaptabilidad para personas con discapacidad en el \u00e1mbito de la educaci\u00f3n superior\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De forma reiterada, este tribunal ha sostenido que la efectividad de la educaci\u00f3n se encuentra circunscrita a la concurrencia de dos complejas dimensiones: una como derecho fundamental, que implica unos derechos-deberes, y otra como servicio p\u00fablico, regido por los principios de eficiencia, continuidad y calidad. A partir de esta doble dimensi\u00f3n de la educaci\u00f3n, se ha reconocido un contenido prestacional, que se concreta en cuatro componentes b\u00e1sicos, a saber: asequibilidad, accesibilidad, adaptabilidad y aceptabilidad, as\u00ed:\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u201cComo derecho y como servicio p\u00fablico, la doctrina nacional e internacional han entendido que la educaci\u00f3n comprende cuatro dimensiones de contenido prestacional:(i) la asequibilidad o disponibilidad del servicio, que puede resumirse en la obligaci\u00f3n del Estado de crear y financiar suficientes instituciones educativas a disposici\u00f3n de todos aquellos que demandan su ingreso al sistema educativo, abstenerse de impedir a los particulares fundar instituciones educativas e invertir en infraestructura para la prestaci\u00f3n del servicio, entre otras; (ii) la accesibilidad, que implica la obligaci\u00f3n del Estado de garantizar el acceso de todos en condiciones de igualdad al sistema aludido, la eliminaci\u00f3n de todo tipo de discriminaci\u00f3n en el mismo, y facilidades para acceder al servicio desde el punto de vista geogr\u00e1fico y econ\u00f3mico; (iii) la adaptabilidad, que se refiere a la necesidad de que la educaci\u00f3n se adapte a las necesidades y demandas de los educandos y que se garantice continuidad en la prestaci\u00f3n del servicio; y (iv) la aceptabilidad, la cual hace alusi\u00f3n a la calidad de la educaci\u00f3n que debe impartirse.\u201d (Resaltos y subrayas propias)65 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Como puede verse, el componente de adaptabilidad consiste en que la educaci\u00f3n debe acomodarse a las necesidades de los estudiantes, de modo que se garantice su permanencia en el servicio educativo, lo que implica \u201cla adopci\u00f3n de medidas que adec\u00faen [\u2026] los programas de aprendizaje a las condiciones requeridas por los estudiantes, en particular, por aquellos que hacen parte de grupos poblacionales de especial protecci\u00f3n\u201d66, tal como la Constituci\u00f3n lo previ\u00f3, de manera expresa, respecto del derecho a la educaci\u00f3n de \u201clas personas con limitaciones f\u00edsicas o mentales, o con capacidades excepcionales\u201d (C.P. art. 68.5). Esto significa, entre otras cosas, que el Estado y las instituciones educativas deben realizar los ajustes razonables necesarios que permitan \u201cque el proceso de aprendizaje se adapte a sus condiciones y en este sentido pued[an] acceder al mismo como cualquier persona\u201d67.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Como es obvio, las personas con discapacidad tambi\u00e9n son titulares del derecho a la educaci\u00f3n. La Sala considera importante destacar que, si bien estas personas necesitan una serie de ajustes razonables, que sean adecuados a sus necesidades, no por ello puede considerarse que su acceso a la educaci\u00f3n sea menos relevante que el de las dem\u00e1s personas. Quien tiene una discapacidad es un ser humano digno y, por tanto, su educaci\u00f3n debe asumirse con la mayor seriedad y cuidado, tanto por el Estado como por las diversas instituciones p\u00fablicas o privadas a quienes se les conf\u00eda la prestaci\u00f3n del servicio p\u00fablico de educaci\u00f3n. Con los debidos ajustes, propios de la adaptabilidad, una persona con discapacidad puede alcanzar los mismos resultados que las dem\u00e1s, e incluso superiores.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>As\u00ed lo ha reconocido este tribunal, en el \u00e1mbito de la educaci\u00f3n universitaria, entre otros casos, al amparar los derechos fundamentales de un alumno con sordoceguera al que la universidad no hab\u00eda accedido a proporcionarle el apoyo de gu\u00edas\u2013int\u00e9rpretes requeridos para continuar con sus estudios68, y al amparar los derechos fundamentales de una estudiante a quien la universidad se hab\u00eda negado a suministrarle el servicio de int\u00e9rprete en lenguaje de se\u00f1as, cuando ella se vio en la imposibilidad econ\u00f3mica de continuar pag\u00e1ndolo por su cuenta, al tiempo que orden\u00f3 efectuar las modificaciones necesarias al plan de estudios y a los esquemas de evaluaci\u00f3n para que la accionante pudiera cumplir con sus deberes, en igualdad de condiciones69.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En los anteriores eventos, se constat\u00f3 que las instituciones educativas no hab\u00edan cumplido su obligaci\u00f3n de llevar a cabo los ajustes razonables necesarios para garantizar el derecho fundamental a la educaci\u00f3n de los estudiantes con discapacidad, por lo que orden\u00f3 implementar recursos materiales y humanos que garantizaran la igualdad entre dicha poblaci\u00f3n y los dem\u00e1s estudiantes, con el fin de garantizar su inclusi\u00f3n en el \u00e1mbito universitario. Adicionalmente, resalt\u00f3 que este mandato debe concretarse mediante el desarrollo de una pol\u00edtica p\u00fablica de educaci\u00f3n inclusiva, que incorpore la garant\u00eda del acceso, la permanencia y la promoci\u00f3n de las personas con discapacidad dentro del sistema de educaci\u00f3n.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.2. Los deberes del Estado y de las instituciones de educaci\u00f3n superior frente a la educaci\u00f3n de las personas con discapacidad\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Los deberes de los Estados frente a la educaci\u00f3n de las personas con discapacidad est\u00e1n previstos en diversos instrumentos del derecho internacional de los derechos humanos, y pueden resumirse as\u00ed: (i) adoptar medidas legislativas, sociales, educativas, laborales o de pol\u00edtica p\u00fablica, y sensibilizar a la poblaci\u00f3n, a trav\u00e9s de medidas \u201cencaminadas a eliminar prejuicios, estereotipos y otras actitudes\u201d que atenten en contra del derecho a la igualdad de estas personas70; (ii) garantizar el acceso y permanencia en el sistema educativo; (iii) permitir que los planes de estudio sean flexibles y adaptables; (iv) proporcionar materiales did\u00e1cticos, de calidad y promover la formaci\u00f3n del personal docente y de apoyo71; (v) prestar el soporte necesario para garantizar la formaci\u00f3n efectiva, lo que incluye adoptar medidas de apoyo personalizadas, y \u201c(\u2026) que se hagan los ajustes razonables en funci\u00f3n de las necesidades individuales\u201d de los estudiantes72. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En el ordenamiento jur\u00eddico interno, en especial, en la Ley 115 de 199473, se prev\u00e9n las siguientes obligaciones a favor de las personas con discapacidad: (1) garantizar en todas las instituciones de educaci\u00f3n p\u00fablica el acceso a la educaci\u00f3n y la capacitaci\u00f3n en los niveles primario, secundario, profesional y t\u00e9cnico; (2) ofrecer formaci\u00f3n integral dentro del ambiente m\u00e1s apropiado a las \u201cnecesidades especiales\u201d de los estudiantes; y (3) fomentar programas para la formaci\u00f3n de docentes y para la adecuada atenci\u00f3n educativa de los menores con capacidades o talentos excepcionales. El Decreto Reglamentario 2082 de 199674 dispone, expl\u00edcitamente, que las instituciones de educaci\u00f3n superior \u201ctendr\u00e1n en cuenta [\u2026] pr\u00e1cticas pedag\u00f3gicas relacionadas con la atenci\u00f3n educativa de las personas con limitaciones o con capacidades o talentos excepcionales en el momento de elaborar los correspondientes curr\u00edculos y planes de estudio\u201d. Por su parte, la Ley 361 de 199775 establece que las instituciones de educaci\u00f3n superior \u201cdeber\u00e1[n] contar con los medios y recursos que garanticen la atenci\u00f3n educativa apropiada\u201d de las personas con discapacidad. \u00a0<\/p>\n<p>En l\u00ednea con lo anterior, la Ley 1618 de 201376 , en el art\u00edculo 11, desarrolla una serie de obligaciones en cabeza del Ministerio de Educaci\u00f3n Nacional (MEN) y de las instituciones de educaci\u00f3n superior. En lo que se refiere al MEN, le corresponde: (a) consolidar la pol\u00edtica de educaci\u00f3n inclusiva y equitativa para las instituciones de educaci\u00f3n superior; (b) incentivar el dise\u00f1o de programas de formaci\u00f3n de docentes regulares para la inclusi\u00f3n educativa y la flexibilizaci\u00f3n curricular y (c) dise\u00f1ar incentivos para que los centros universitarios destinen recursos humanos y econ\u00f3micos al desarrollo de tecnolog\u00edas inclusivas. Las instituciones de educaci\u00f3n, por su parte, deber\u00e1n \u201cpropugnar por aplicar progresivamente recursos de su presupuesto para vincular recursos humanos, recursos did\u00e1cticos y pedag\u00f3gicos que apoyen la inclusi\u00f3n educativa\u201d, promover la capacitaci\u00f3n y sensibilizaci\u00f3n del personal docente, y \u201casignar recursos financieros para el dise\u00f1o y ejecuci\u00f3n de programas educativos que utilicen las nuevas tecnolog\u00edas de la informaci\u00f3n\u201d, entre otras. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En cumplimiento de las obligaciones previstas en la citada Ley 1618 de 2013, el MEN expidi\u00f3 el documento \u201cLineamientos Pol\u00edtica de Educaci\u00f3n Superior Inclusiva\u201d, que establece como caracter\u00edsticas de la educaci\u00f3n inclusiva las de participaci\u00f3n, diversidad, interculturalidad, equidad, calidad y pertinencia, al tiempo que resalta los principios de integralidad y flexibilidad en el marco de la autonom\u00eda universitaria, por cuanto \u201cbuscan promover el acceso, la permanencia y la graduaci\u00f3n de estudiantes pertenecientes a los diferentes grupos priorizados, focaliz\u00e1ndose en las barreras para el aprendizaje y la participaci\u00f3n propias del sistema\u201d. El documento define el principio de integralidad como \u201cla amplia dimensi\u00f3n de estrategias y l\u00edneas de acci\u00f3n que deben ser identificadas\u201d para garantizar la inclusi\u00f3n que, a su vez, comprende los subprincipios de calidad y pertinencia, y se\u00f1ala que el principio de flexibilidad \u201cse relaciona a la adaptabilidad para responder a la diversidad cultural y social [\u2026] y por ello los lineamientos deben ser susceptibles de revisi\u00f3n, modificaci\u00f3n y permanente actualizaci\u00f3n como parte procesal de la educaci\u00f3n inclusiva\u201d 77. \u00a0\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Los lineamientos tambi\u00e9n establecen estrategias para la implementaci\u00f3n de ambientes educativos inclusivos as\u00ed como acciones espec\u00edficas para dichas estrategias y para cada uno de los grupos poblacionales priorizados por el MEN, entre estos las personas con discapacidad; esto con el fin de promover una pol\u00edtica de educaci\u00f3n superior inclusiva en el pa\u00eds. Dentro de las estrategias se mencionan las dirigidas a a) generar procesos acad\u00e9micos inclusivos, b) contar con profesores inclusivos, c) promover espacios de investigaci\u00f3n, arte y cultura con enfoque de educaci\u00f3n inclusiva, d) construir una estructura administrativa y financiera que sustente las acciones de educaci\u00f3n inclusiva, y e) dise\u00f1ar una pol\u00edtica institucional inclusiva. Y como acciones espec\u00edficas de impulso a las estrategias se plantean la creaci\u00f3n o modificaci\u00f3n de programas acad\u00e9micos y fortalecimiento de procesos acad\u00e9micos y administrativos con enfoque de educaci\u00f3n inclusiva, la aplicaci\u00f3n del \u00cdndice de Inclusi\u00f3n Para Educaci\u00f3n Superior (INES)78 y articulaci\u00f3n con los proyectos de regionalizaci\u00f3n de la educaci\u00f3n superior79. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Para determinar las acciones espec\u00edficas en favor de la poblaci\u00f3n estudiantil con discapacidad, el documento identifica las principales barreras de acceso, permanencia, pertinencia y calidad que impiden su educaci\u00f3n inclusiva siendo algunas de estas: i) la insuficiencia de los servicios y apoyos profesionales complementarios que faciliten su adaptaci\u00f3n a la universidad (permanencia); ii) la carencia de una oferta acad\u00e9mica espec\u00edfica y de participaci\u00f3n en el dise\u00f1o y construcci\u00f3n de propuestas curriculares diferenciadas (pertinencia); iii) el escaso avance en accesibilidad de la oferta acad\u00e9mica a trav\u00e9s de las TIC y de metodolog\u00edas flexibles (pertinencia); iv) la falta de formaci\u00f3n diferencial para docentes y la comunidad educativa (calidad); v) la insuficiente investigaci\u00f3n sobre las condiciones de acceso, permanencia y promoci\u00f3n de estudiantes con discapacidad en el \u00e1mbito de la educaci\u00f3n superior (calidad); vi) la ausencia de condiciones pedag\u00f3gicas adecuadas que fomenten la permanencia (calidad)80. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3. Examen del caso concreto \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3.1. En esta oportunidad, la Sala Tercera de Revisi\u00f3n debe decidir si la Universidad Tecnol\u00f3gica de Pereira vulner\u00f3 los derechos dignidad humana, a la igualdad material y a la educaci\u00f3n de Catalina Celis Rivera, al no dar cumplimiento a la propuesta de acompa\u00f1amiento acad\u00e9mico formulada por UTP en el a\u00f1o 2016, para atender la situaci\u00f3n concreta de la estudiante; en otras palabras, debe establecerse si la UTP ha desconocido o no el derecho de una estudiante con discapacidad a permanecer en el sistema educativo, a partir de la obligaci\u00f3n que le asiste a las instituciones de educaci\u00f3n superior de realizar ajustes razonables adecuados a sus necesidades.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3.2. En primer t\u00e9rmino, se tiene: i) que la accionante es una persona mayor de edad con discapacidad; ii) que en el a\u00f1o 2015 ingres\u00f3 al programa de Medicina Veterinaria y Zootecnia en la UTP; iii) que desde entonces ha cursado esta carrera de forma ininterrumpida, encontr\u00e1ndose matriculada en el s\u00e9ptimo semestre acad\u00e9mico para el segundo semestre de 2020; iv) que desde el comienzo de sus estudios la accionante ha requerido de la universidad ajustes y apoyos educativos, para adelantar sus estudios, por las dificultades de aprendizaje que ostenta y por su condici\u00f3n de salud, que la ha llevado a ausentarse de clases y, en algunas ocasiones, a tener que someterse a tratamientos en hospitalizaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3.3. En segundo t\u00e9rmino, se tiene: v) que, desde el a\u00f1o 2016, como respuesta a un fallo de tutela anterior en favor de la accionante, la universidad formul\u00f3 la \u201cPropuesta Acompa\u00f1amiento a Catalina Celis Rivera Desde la Universidad Tecnol\u00f3gica de Pereira y la Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario\u201d.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3.4. La propuesta de la UTP, tiene los siguientes elementos: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u201c- Se realizar[\u00e1] un primer proceso de acercamiento con la estudiante, para saber las expectativas y el auto conocimiento de su discapacidad, as\u00ed como la autorizaci\u00f3n y aprobaci\u00f3n del proceso que se iniciar[\u00e1]. \/\/ As\u00ed mismo se citar[\u00e1] a la madre-acudiente para indagar las expectativas de ella con el proceso de aprendizaje de la estudiante teniendo en cuenta las caracter\u00edsticas individuales de Catalina Celis Rivera. \/\/ (Cita prioritaria con la Psic\u00f3loga del PAI Mar\u00eda Zully Serna Mahecha)\u00a0 \u00a0<\/p>\n<p>&#8211; Iniciar el proceso de intervenci\u00f3n para conocer el estilo de aprendizaje que posee la estudiante y as\u00ed orientar el trabajo a realizar pedag\u00f3gicamente. \/\/ Teniendo como base la verificaci\u00f3n y fecha de la \u00faltima evaluaci\u00f3n que determina el C.I. Coeficiente Intelectual de la estudiante (Lo debe facilitar la familia). \/\/ Nosotros desde la UTP aplicaremos con el apoyo de las Psic\u00f3logas del PAI el instrumento WAIS. Qu[\u00e9] es el WAIS, la Escala Weshsler de Inteligencia para Adultos (WAIS) es un test psicom\u00e9trico el cual nos provee cuatro puntuaciones (Comprensi\u00f3n Verbal, Razonamiento Perceptivo, Memoria de Trabajo y Velocidad de Procesamiento), y una quinta que se denomina Cociente Intelectual Total.\u00a0 \u00a0<\/p>\n<p>&#8211; Se requiere de acompa\u00f1amiento permanente y cooparticipativo (sic) Universidad-familia con el fin de implementar estrategias al interior de su n\u00facleo familiar teniendo como objetivo fortalecer las habilidades acad\u00e9micas necesarias para su desempe\u00f1o integral dentro de la UTP.\u00a0 \u00a0<\/p>\n<p>&#8211; Se brindar\u00e1 formaci\u00f3n y asesor\u00eda, a los docentes del programa acad\u00e9mico de Veterinaria sobre la discapacidad que posee la estudiante, las caracter\u00edsticas propias y estrategias pedag\u00f3gicas para que acceda con mayor facilidad a los nuevos aprendizajes. (se contar[\u00e1] con la profesional en Fonoaudiolog\u00eda y Magister en Educaci\u00f3n Martha Luc\u00eda Garz\u00f3n, adscrita a la Maestr\u00eda de Educaci\u00f3n e Inclusi\u00f3n). \u00a0 \u00a0<\/p>\n<p>&#8211; Se le asign\u00f3 como monitora permanente de apoyo a estudios, lecturas y trabajos a la estudiante del programa de Medicina Veterinaria y Zootecnia (\u2026). \/\/ &#8211; A partir del segundo semestre acad\u00e9mico del a\u00f1o 2016, se contar[\u00e1] con dos estudiantes del programa de Lic. En Pedagog\u00eda Infantil, las cuales se han desempe\u00f1ado como monitoras acad\u00e9micas de la materia Necesidades Educativas Especiales (\u2026), las cuales contar[\u00e1]n con la supervisi\u00f3n de la docente Martha Luc\u00eda Garz\u00f3n, experta en el tema, ellas ofrecer\u00e1n un acompa\u00f1amiento permanente con respecto a la utilizaci\u00f3n de estrategias y medios requeridos para potenciar las habilidades intelectuales que la estudiante debe fortalecer y reforzar. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>&#8211; Despu\u00e9s de la formaci\u00f3n que se le ofrecer\u00e1 a docentes y directivos, se espera contar con la sensibilizaci\u00f3n y el abordaje adecuado de la discapacidad con la que cuenta la estudiante, haciendo \u00e9nfasis y garantizando que (sic) un curr\u00edculo y m\u00e9todos de evaluaci\u00f3n diferencial, manejo de horarios y tiempos extendidos para tareas y trabajos. Con el objetivo de tener en cuenta su estilo de aprendizaje, fortalezas y la utilizaci\u00f3n de herramientas que le permitan demostrar sus competencias.\u00a0 \u00a0<\/p>\n<p>Martha Luc\u00eda Villabona Bayona. Psic\u00f3loga\/Profesional Universitario. Responsable proceso de Acompa\u00f1amiento Integral de la comunidad en situaci\u00f3n de discapacidad UTP. Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario\u201d. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3.5. Dentro de este contexto, en el presente caso se controvierte sobre el cumplimiento o incumplimiento de algunos componentes de dicha propuesta. Para analizar esta cuesti\u00f3n, la Sala considera que el examen de los componentes y de su cumplimiento no puede hacerse de forma aislada, como lo pretende la accionante, sino de manera conjunta, ya que la referida propuesta est\u00e1 formulada como un conjunto concatenado de acciones afirmativas espec\u00edficas para el caso de la estudiante.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3.6. Frente al cumplimiento de la \u201cPropuesta Acompa\u00f1amiento a Catalina Celis Rivera desde la Universidad Tecnol\u00f3gica de Pereira y la Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario\u201d81, la UTP insiste en haber desplegado todo lo que ha estado a su alcance para llevar a cabo los distintos componentes de ella, pero, por situaciones ajenas a su voluntad, no ha podido dar cumplimiento a todos. En concreto, se\u00f1ala que la estudiante y su madre no han asistido a las citas programadas por la psic\u00f3loga y la fonoaudi\u00f3loga del Programa de Acompa\u00f1amiento Institucional (PAI), y tampoco han aportado pruebas neuropsicol\u00f3gicas actualizadas que son necesarias para identificar las necesidades educativas de Catalina Celis Rivera. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Al respecto, en el informe de seguimiento de julio de 2016, la profesional del PAI se\u00f1al\u00f3 que realiz\u00f3 acercamiento inicial con la estudiante y con su madre por separado, quienes manifestaron estar de acuerdo con el proceso de acompa\u00f1amiento y el trabajo colaborativo universidad-estudiante-acudiente. Y relat\u00f3 que los antecedentes cl\u00ednicos de la estudiante presentados por su madre datan de 2005 a 201082, es decir, que tienen m\u00e1s de cinco a\u00f1os de dictaminados, por lo que expidi\u00f3 una orden de remisi\u00f3n a especialistas para valoraci\u00f3n por neuropsicolog\u00eda, con el fin de que fuera tramitada por la madre ante la E.P.S. de la estudiante83. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Sin embargo, seg\u00fan la comunicaci\u00f3n dirigida a la UTP el 13 de julio de 2016, la se\u00f1ora Miriam Rivera manifest\u00f3 estar en desacuerdo con la exigencia de la universidad de presentar una nueva valoraci\u00f3n neuropsicol\u00f3gica, al no contar con los recursos econ\u00f3micos para pagarla84, \u201cya que tiene un costo que oscila entre los $420.000 y $500.000, e igualmente [se\u00f1al\u00f3] que las Entidades Competentes establecidas por la leyes colombianas, son las que han [proferido] el dictamen, como lo plasma el art\u00edculo 142 del Decreto-Ley 019 de 2012\u201d. Asimismo, expuso que tanto ella como su hija no atendieron el acompa\u00f1amiento en el espacio psicoterap\u00e9utico ofrecido por la universidad, a trav\u00e9s del PAI, en su propuesta, debido a que la instituci\u00f3n \u201crompi\u00f3 el pacto de confidencialidad de terapia y tratamiento terap\u00e9utico\u201d85. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En respuesta a este requerimiento, mediante comunicaci\u00f3n del 11 de septiembre de 2016, la se\u00f1ora Miriam Rivera inform\u00f3 a la UTP que, cuando interpuso la tutela de 2016, present\u00f3 la valoraci\u00f3n de neuropsicolog\u00eda \u201crealizada por el ente competente EPS S.O.S. para la respectiva valoraci\u00f3n de p\u00e9rdida de capacidad laboral, adem\u00e1s, [se entreg\u00f3] de dicha valoraci\u00f3n con la historia cl\u00ednica ante la Universidad\u201d. Tambi\u00e9n indic\u00f3 que solicit\u00f3 ante el m\u00e9dico general y la m\u00e9dica familiar de la E.P.S. de su hija, la orden de valoraci\u00f3n por neuropsicolog\u00eda, obteniendo una respuesta negativa. E insisti\u00f3 en no contar con los recursos econ\u00f3micos para costearla de manera particular87.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De acuerdo con las comunicaciones internas de la universidad de septiembre de 2016, la instituci\u00f3n educativa ten\u00eda claro que la madre de la estudiante no aportar\u00eda la valoraci\u00f3n por neuropsicolog\u00eda actualizada que le hab\u00eda requerido, por lo que plante\u00f3 la realizaci\u00f3n de una valoraci\u00f3n por fonoaudiolog\u00eda con una profesional de la universidad, a fin de avanzar en el proceso de acompa\u00f1amiento. No obstante, en el expediente no reposa dicha valoraci\u00f3n88. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3.7. Con todo, a pesar de la aparente falta de realizaci\u00f3n del procedimiento en cita, lo cierto es que la estudiante, con el apoyo de su madre, ha implementado estrategias propias para cumplir con sus labores acad\u00e9micas, al tiempo que ha contado con el apoyo de la universidad para avanzar en el plan de estudios, tal como lo manifiesta en la declaraci\u00f3n de parte que de forma directa rindi\u00f3 en este proceso, en sede de revisi\u00f3n (supra 2.3.). Dentro de las estrategias propias, se encuentra la ayuda constante de su madre quien le hace todo m\u00e1s l\u00fadico y, por recomendaci\u00f3n de su m\u00e9dico tratante, matricula por semestre la mitad o menos de las asignaturas del plan de estudios. Adem\u00e1s, graba las clases y luego las oye, escribe y reescribe para memorizar los contenidos, despu\u00e9s los lee y relee hasta que logra entender. Tambi\u00e9n acude a internet en b\u00fasqueda de material con contenido visual y auditivo, o textos que presenten los contenidos de manera distinta y que le resulten m\u00e1s f\u00e1cilmente comprensibles. Se demora entre dos o tres horas estudiando un tema, luego debe repesarlo, por lo cual le pide a su madre que le lea (\u201cporque escuchando se [l]e graba m\u00e1s\u201d) o que realicen talleres para reforzar lo estudiado. Por lo dem\u00e1s, la estudiante afirma que cuando no entiende alg\u00fan contenido acad\u00e9mico pide explicaci\u00f3n directa al profesor e indica que para realizar trabajos o preparar ex\u00e1menes, cuenta con la ayuda de un monitor personal que es un estudiante de la misma carrera, o se apoya en sus compa\u00f1eras de clase o investiga en libros e internet. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En igual sentido, la universidad ha reconocido las dificultades de aprendizaje de la estudiante, por lo que le ha facilitado el apoyo de profesores y compa\u00f1eros del programa, y ha sensibilizado y capacitado a los docentes frente a la situaci\u00f3n de vulnerabilidad de la estudiante y la necesidad de efectuar adecuaciones al curr\u00edculo. Con respecto a las actuaciones adelantadas por la instituci\u00f3n educativa, sobre la base del material probatorio recaudado en el tr\u00e1mite de tutela, qued\u00f3 demostrado que, durante la mayor parte del tiempo que la joven ha permanecido en la universidad, ha adoptado el dise\u00f1o e implementaci\u00f3n de un n\u00famero considerable de medidas afirmativas. As\u00ed, en el transcurso del plan de estudios, le ha otorgado beneficios sociales (bonos de transporte y alimentaci\u00f3n) y la incluy\u00f3 como destinataria de la \u201cPol\u00edtica institucional de inclusi\u00f3n con enfoque en discapacidad\u201d, adoptada mediante el Acuerdo N\u00famero 26 del Consejo Superior del 9 de junio de 2020, dentro de la caracterizaci\u00f3n de estudiantes matriculados con discapacidad \u201ccognitiva-psicosocial\u201d. Adicionalmente, tambi\u00e9n le ha garantizado la reducci\u00f3n en el pago del valor de la matr\u00edcula, producto del estudio socioecon\u00f3mico realizado al hogar de la accionante, y le ha asignado un monitor de estudios, en cumplimiento de \u00f3rdenes dictadas en oportunidades anteriores por jueces de tutela que han amparado los derechos de la estudiante como sujeto de especial protecci\u00f3n constitucional. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Asimismo, la UTP le ha brindado a la estudiante los siguientes apoyos, asesor\u00edas, asistencias y ajustes para facilitar el curso del plan de estudios del programa de Medicina Veterinaria y Zootecnia: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>i) La exoner\u00f3 del proceso de corresponsabilidad del servicio social y le ajust\u00f3 la regla que exige rendimiento acad\u00e9mico para mantener el bono de transporte. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>ii) Le ha asignado monitorias sociales desde el 2016 hasta el 2020, aumentando el n\u00famero de horas semanales a partir del a\u00f1o 2019, como se evidencia en la siguiente tabla: \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>PERIODO \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>RESOLUCI\u00d3N \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p># HORAS SEMANA \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>VALOR MONITORIA \u00a0\u00a0<\/p>\n<p>2016-1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>No. 24 del 19 mayo al 10 de junio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>24 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>$ 357.280 (x 70 horas) \u00a0\u00a0<\/p>\n<p>2016-2 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>No. 45 del 16 de agosto al 16 de diciembre \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>12 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>$ 1.102.464 (x 216 horas \u00a0\u00a0<\/p>\n<p>2017-1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>No. 14 del 1 de marzo al 10 de junio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>12 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sin informaci\u00f3n \u00a0\u00a0<\/p>\n<p>2017-2 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>No. 71 del 16 de agosto al 7 de diciembre \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>12 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>$ 1.113.840 (x 240 horas) \u00a0\u00a0<\/p>\n<p>2018-1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>No. 22 del 20 de febrero al 9 de junio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>12 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>$ 1.179.120 (x 240 horas) \u00a0\u00a0<\/p>\n<p>No. 81 del 29 de agosto al 13 de diciembre \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>12 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>$ 1.317.840 (x 228 horas) \u00a0\u00a0<\/p>\n<p>2019-1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>No. 34 del 8 de abril al 20 de julio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>15 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>$ 1.287.300 (x 210 horas) \u00a0\u00a0<\/p>\n<p>2019-2 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>No. 86 del 20 de agosto al 13 de diciembre \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>20 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>$ 2.206.800 (x 355 horas) \u00a0\u00a0<\/p>\n<p>2020-1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sin informaci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>20 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>$ 1.696.500 (x 261 horas) \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>iii) Sensibiliz\u00f3 y capacit\u00f3 a los docentes del programa en inclusi\u00f3n educativa y adecu\u00f3 el curr\u00edculo a sus necesidades espec\u00edficas. Precisamente, en la respuesta a los requerimientos de esta Sala de Revisi\u00f3n, remitida el 27 de julio de 2020, el rector y representante legal de la UTP afirm\u00f3 que: \u201c[l]os docentes del programa recibieron capacitaci\u00f3n en discapacidad desde un comienzo. Se han hecho las adaptaciones pedag\u00f3gicas pertinentes y todos los docentes est\u00e1n concientizados del tratamiento excepcional que se debe dar a la estudiante\u201d. Y adjunta la presentaci\u00f3n sobre inclusi\u00f3n educativa que reciben en el proceso de inducci\u00f3n los docentes que se vinculan a la universidad. Igualmente, en sede de instancia, el rector encargado de la UTP asegur\u00f3 que la estudiante Celis Rivera ten\u00eda \u201cun tratamiento acad\u00e9mico especial, [el cual] (\u2026) tambi\u00e9n se le aplica (\u2026) [en las evaluaciones]\u201d 89.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3.8. En este orden de ideas, en criterio de esta Sala no cabe duda de que tanto la estudiante como su madre acudiente y la universidad han abonado esfuerzos significativos para que la primera logre avanzar en el programa de pregrado escogido, pues no de otra manera se explica el hecho de que la joven Celis Rivera haya podido cumplir con el plan de estudios desde su comienzo, en el a\u00f1o 2015, y est\u00e9 cursando su s\u00e9ptimo semestre acad\u00e9mico en la anualidad actual, habiendo superado incluso una sanci\u00f3n acad\u00e9mica.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Pese a lo que se ha dicho sobre el aparente abandono y desatenci\u00f3n del proceso de acompa\u00f1amiento psicopedag\u00f3gico, por la accionante y su acudiente, en la respuesta a las pruebas ordenadas por la Sala, la acudiente sostiene que: \u201ccomo madre y cuidadora, [se] comunic[a] constantemente con varios de los profesionales de Vicerrector\u00eda de Bienestar Universitario, asist[e] a las \u00a0reuniones y citas que [le] son programadas\u201d y \u201cla estudiante asiste a terapias con los profesionales PAI, como lo puede determinar la firma de asistencia \u00a0e historia de la estudiante\u201d. Adem\u00e1s, la universidad ha reconocido el ritmo de aprendizaje propio de la estudiante, aceptando que la joven matricule por semestre la mitad de asignaturas del pensum acad\u00e9mico, conforme a lo que recomienda su m\u00e9dico tratante. Y lo que es m\u00e1s importante, a pesar de las dificultades existentes, la estudiante ha podido avanzar en su proceso educativo, lo que indica que la tarea de la UPT y de la propia accionante, han venido dando resultados. \u00a0\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>No obstante, la Sala advierte que el proceso colaborativo y coparticipativo entre \u201cUniversidad-familia-estudiante\u201d, en el que se soporta la propuesta de acompa\u00f1amiento acad\u00e9mico formulada por la universidad90, se ha visto afectado por la ruptura del di\u00e1logo y los desacuerdos entre las partes. Por ejemplo, frente a la necesidad de contar con una valoraci\u00f3n actualizada de capacidades de la estudiante, se aprecia varios periodos de aparente distanciamiento, dado que, al parecer, solo existi\u00f3 un intercambio de comunicaciones entre la acudiente y la universidad, entre los a\u00f1os 2017 y 2018, ya que ninguna otra prueba obra en el expediente. Ante esta ruptura y desacuerdo, se ha hecho dif\u00edcil establecer acciones concretas de orientaci\u00f3n pedag\u00f3gica que puedan ser objeto de seguimiento y evaluaci\u00f3n permanentes.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Por los anteriores motivos, no resulta exigible exclusivamente a la universidad el cumplimiento efectivo de los componentes de la \u201cPropuesta Acompa\u00f1amiento a Catalina Celis Rivera Desde la Universidad Tecnol\u00f3gica de Pereira y la Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario\u201d que se demanda, ya que, se reitera, dicha propuesta est\u00e1 formulada como un conjunto concatenado de acciones afirmativas espec\u00edficas para el caso de la estudiante, si se quiere por fases, que depende del concurso de las partes y de la suma de sus esfuerzos simult\u00e1neos entre \u201cUniversidad-familia-estudiante\u201d. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>7.3.9. De esta manera, la Sala no advierte que la UTP haya vulnerado los derechos dignidad humana, a la igualdad material y a la educaci\u00f3n de la accionante. Por el contrario, advierte que la UTP ha hecho ingentes esfuerzos por brindar los apoyos y efectuar los ajustes que est\u00e1n a su alcance, para contribuir con el proceso formativo de la estudiante, reclamando la corresponsabilidad propia que les asistes a las familias, como lo dispone el art\u00edculo 67 del Texto Superior, en cuyo aparte pertinente se\u00f1ala que: \u201cEl Estado, la sociedad y la familia son responsables de la educaci\u00f3n (\u2026)\u201d91.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>De hecho, los esfuerzos conjuntos de la universidad, la familia y la estudiante muestran, hasta ahora, resultados destacables, en la medida en que la accionante ha podido permanecer en el sistema educativo y, con los ajustes necesarios, ha podido superar con \u00e9xito varios semestres de su carrera profesional. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>A pesar de lo anterior, la ruptura y los desacuerdos entre los involucrados, pueden llegar a afectar la situaci\u00f3n de la estudiante. Por ello, es imperativo restablecer el di\u00e1logo entre ellos y lograr un acercamiento significativo, no s\u00f3lo para mantener las medidas ya adoptadas, sino para adaptarlas a las necesidades actuales de la estudiante, que ahora debe hacer frente a la etapa final de su plan de estudios y prepararse para su egreso.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>En este sentido, la Sala ha podido verificar que la UTP incluy\u00f3 a la joven Catalina Celis Rivera como destinataria de la \u201cPol\u00edtica institucional de inclusi\u00f3n con enfoque en discapacidad\u201d, adoptada mediante el Acuerdo N\u00famero 26 del Consejo Superior del 9 de junio de 2020, dentro de la caracterizaci\u00f3n de estudiantes matriculados con discapacidad \u201ccognitiva-psicosocial\u201d.\u00a0 Este tipo de actos dan cuenta del compromiso de la universidad para garantizar que la estudiante culmine su ciclo lectivo y pueda graduarse del programa de pregrado en el cual se encuentra inscrita.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>No obstante, la Sala debe destacar que las medidas deben tener continuidad y, por tanto, instar\u00e1 a la UTP a que, en lo sucesivo, contin\u00fae brindado los apoyos y ajustes que requiera Catalina Celis Rivera, a fin de avanzar en su proceso educativo. En especial, se le recomendar\u00e1 a la UTP liderar el di\u00e1logo o los acercamientos con la estudiante y su acudiente, a fin de actualizar las medidas de acompa\u00f1amiento acad\u00e9mico de acuerdo con las necesidades espec\u00edficas de la estudiante para, en lo posible, pueda continuar con su proceso educativo. Esto debe realizarse conforme al marco establecido en la \u201cPol\u00edtica institucional de inclusi\u00f3n con enfoque en discapacidad\u201d de la UTP, adoptada mediante el Acuerdo N\u00famero 26 del Consejo Superior del 9 de junio de 2020. Adem\u00e1s de las medidas que correspondan, debe establecerse el seguimiento adecuado de las mismas y asegurarse el presupuesto para la aplicaci\u00f3n de las acciones afirmativas que correspondan.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>DECISI\u00d3N \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>Con fundamento en las consideraciones expuestas en la presente sentencia, la Sala Tercera de Revisi\u00f3n de la Corte Constitucional, administrando justicia en nombre del pueblo y por mandato de la Constituci\u00f3n \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>RESUELVE\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>PRIMERO.- En lo que respecta a la pretensi\u00f3n relacionada con la asignaci\u00f3n del monitor, CONFIRMAR PARCIALMENTE la sentencia proferida el 10 de octubre de 2019 por la Sala Tercera de Decisi\u00f3n Laboral del Tribunal Superior del Distrito Judicial de Pereira, que declar\u00f3 la cosa juzgada constitucional y revoc\u00f3 la decisi\u00f3n proferida el 2 de septiembre de 2019, por el Juzgado Quinto Laboral del Circuito de Pereira, en la que se deneg\u00f3 el amparo.\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>SEGUNDO.- En lo referente a la pretensi\u00f3n de anular o cancelar la sanci\u00f3n acad\u00e9mica de per\u00edodo en transici\u00f3n impuesta a Catalina Celis Rivera por la p\u00e9rdida del primer semestre de 2019, REVOCAR el amparo concedido en la sentencia proferida el 10 de octubre de 2019 por la Sala Tercera de Decisi\u00f3n Laboral del Tribunal Superior del Distrito Judicial de Pereira y, en su lugar, DECLARAR la carencia actual de objeto, por las razones expuestas en esta providencia. \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>CUARTO.- Por Secretar\u00eda General de esta Corporaci\u00f3n, L\u00cdBRENSE las comunicaciones de que trata el art\u00edculo 36 del Decreto 2591 de 1991. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>C\u00f3piese, notif\u00edquese, comun\u00edquese y c\u00famplase. \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>LUIS JAVIER MORENO ORTIZ\u00a0 \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>ALEJANDRO LINARES CANTILLO \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>ANTONIO JOS\u00c9 LIZARAZO OCAMPO \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0<\/p>\n<p>Secretaria General \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 Los hechos se describen a partir del contenido expuesto en el escrito de tutela y sus anexos, en las pruebas allegadas durante el tr\u00e1mite de primera y segunda instancia, en el escrito de solicitud de selecci\u00f3n presentado por la accionante y en los elementos de convicci\u00f3n que fueron presentados en sede de revisi\u00f3n. \u00a0<\/p>\n<p>2 La expresi\u00f3n \u201cpersonas con discapacidad\u201d es la adecuada y recomendada, de acuerdo con el art\u00edculo 1 de la Convenci\u00f3n Internacional sobre los Derechos de las Personas con Discapacidad, para referirse a quienes \u201ctengan deficiencias f\u00edsicas, mentales, intelectuales o sensoriales a largo plazo que, al interactuar con diversas barreras, puedan impedir su participaci\u00f3n plena y efectiva en la sociedad, en igualdad de condiciones con las dem\u00e1s\u201d. \u00a0<\/p>\n<p>3 La se\u00f1ora Catalina Celis presenta estados de angustia, ansiedad y depresi\u00f3n, tal como lo afirma su se\u00f1ora madre. Ver folio 33, cuaderno uno. En an\u00e1lisis del m\u00e9dico psiquiatra, en el a\u00f1o 2015, registra paciente con RM m\u00e1s trastornos emocionales y comportamentales. Folio 26, cuaderno uno. En cuanto a su aspecto emocional, la estudiante ha evidenciado crisis nerviosas y le han encontrado lesiones por cutting. Adem\u00e1s, ha manifestado tener dependencia a medicamentos prescritos y pensamientos suicidas en contra de su voluntad. Folio 75, cuaderno 1.\u00a0 \u00a0<\/p>\n<p>4 Acci\u00f3n de tutela promovida ante el Juzgado Quinto Civil del Circuito de Pereira, radicado No. 2015-00130, fallo del 14 de mayo de 2015, decisi\u00f3n que confirm\u00f3 el Tribunal Superior de Pereira, Sala Civil Familia, mediante fallo del 3 de julio de 2015. Anexo en digital dentro del expediente, CD folio 59, cuaderno 1. \u00a0<\/p>\n<p>5 Acci\u00f3n de tutela promovida ante el Juzgado Primero Penal del Circuito para Adolescentes de Pereira, radicado No. 2016-015, fallo del 23 de febrero de 2016, que neg\u00f3 el amparo invocado, decisi\u00f3n que revoc\u00f3 el Tribunal Superior de Pereira, Sala No. 5 de Asuntos Penales para Adolescentes, mediante fallo del 11 de abril de 2016. Folios 171 a 182, cuaderno 1. \u00a0<\/p>\n<p>6 El documento denominado \u201cPropuesta Acompa\u00f1amiento a Catalina Celis Rivera Desde la Universidad Tecnol\u00f3gica de Pereira y la Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario\u201d, fue aportado tanto por la parte accionante (folios 22 y 23, cuaderno uno) como accionada (folios 76 y 77, cuaderno 1).\u00a0 \u00a0<\/p>\n<p>7 En la Escala Wechsler de Inteligencia para Adultos (WAIS), prueba IV aplicada, Catalina Celis Rivera obtuvo un coeficiente intelectual con promedio de 58, que la ubica en un nivel deficiente. Se le diagnostic\u00f3 un \u201cRetraso Mental con predominancia Leve, con eventos emocionales de percepci\u00f3n negativos\u201d. Folios 82 a 85, cuaderno 1. \u00a0<\/p>\n<p>8 As\u00ed lo afirm\u00f3 la estudiante en la declaraci\u00f3n directa rendida, el 24 de julio de 2020, ante el Juzgado Quinto Laboral del Circuito de Pereira. \u00a0<\/p>\n<p>9 La E.P.S. a la que se encuentran afiliadas es Servicio Occidental de Salud -S.O.S-.\u00a0 \u00a0<\/p>\n<p>10 De acuerdo con el estudio socioecon\u00f3mico efectuado por la Universidad Tecnol\u00f3gica de Pereira en el a\u00f1o 2015, los ingresos mensuales de la se\u00f1ora Miriam Rivera Osorio eran de $825.000 producto de una pensi\u00f3n por invalidez, con los cuales debe atender gastos de arriendo de vivienda as\u00ed como de transporte a consultas y tratamientos, copagos, medicamentos excluidos del POS y alimentaci\u00f3n vegetariana para su hija. De acuerdo con el estudio mencionado: \u201c[l]a madre debi\u00f3 retirarse de su trabajo desde hace 5 a\u00f1os para atender a la hija; el ingreso que recibe es de la pensi\u00f3n que le adelantaron por la discapacidad de la hija, porque debe tener atenci\u00f3n permanente\u201d. Folio 214, cuaderno uno. La situaci\u00f3n econ\u00f3mica de la accionante y su acudiente no ha variado, tal como lo afirma la se\u00f1ora Rivera Osorio en el escrito de respuesta al traslado de las pruebas decretadas en sede de revisi\u00f3n. \u00a0<\/p>\n<p>11 De acuerdo con el historial acad\u00e9mico, Catalina Celis Rivera ha aprobado los semestres lectivos con las siguientes calificaciones: primer semestre 2015 (3.4), primer semestre 2016 (4.2), segundo semestre 2016 (3.6), primer semestre 2017 (3.3), segundo semestre 2017 (3.3), primer semestre 2018 (3.4), segundo semestre 2018 (3.9). \u00a0<\/p>\n<p>12 Afirmaci\u00f3n realizada por la se\u00f1ora Miriam Rivera. Ver folio 31, cuaderno uno. \u00a0<\/p>\n<p>13 Las asignaturas cursadas y no aprobadas durante el primer semestre de 2019 fueron: biolog\u00eda celular y molecular (2,1), fisiolog\u00eda general (0.7), medicina interna de grandes animales (2,7) y cirug\u00eda II (2,4). Folio 24, cuaderno 1. \u00a0<\/p>\n<p>14 Folios 45 y 128, cuaderno 1. \u00a0<\/p>\n<p>15 Universidad Tecnol\u00f3gica de Pereira. Resoluci\u00f3n de Rector\u00eda No. 1785 del 03 de abril de 2019 \u201cPor medio de la cual se facilita la aplicaci\u00f3n de la reglamentaci\u00f3n vigente del semestre de transici\u00f3n y se dictan otras disposiciones\u201d. \u201cArt\u00edculo primero. Semestre de Transici\u00f3n. Son causales para quedar en semestre de transici\u00f3n las siguientes: 1. Perder la misma asignatura pr\u00e1ctica en tres (03) oportunidades o m\u00e1s. 2. Terminar un periodo acad\u00e9mico con un promedio semestral inferior a dos coma cinco (2,5). 3. Quedar en calidad de PRUEBA por dos (2) periodos consecutivos o no. 4. Perder una asignatura Te\u00f3rico Pr\u00e1ctica en dos ocasiones con nota inferior a dos coma cero (2,0). 5. Perder la prueba de validaci\u00f3n de la asignatura Te\u00f3rico Pr\u00e1ctica. 6. Perder por segunda vez el semestre de cr\u00e9ditos reducidos, en los t\u00e9rminos establecidos en el art\u00edculo 5\u00ba de la Resoluci\u00f3n 626 de marzo 15 de 2019, o la que la modifique o adicione. Par\u00e1grafo I: En los casos previstos en el presente art\u00edculo, independientemente de si matricula o no la asignatura Te\u00f3rico Pr\u00e1ctica o, Pr\u00e1ctica, el estudiante ingresa a semestre de transici\u00f3n, en el cual continuar\u00e1 hasta tanto matricule y apruebe dicha asignatura. En caso de matricularla y no aprobarla, quedar\u00e1 FUERA un semestre. Una vez reingrese y matricule la asignatura, si la pierde nuevamente quedar\u00e1 FUERA del programa definitivamente. Par\u00e1grafo II: Quien pierde la asignatura Te\u00f3rico Pr\u00e1ctica por tercera vez, solamente podr\u00e1 cursar dicha asignatura en curso intersemestral o curso dirigido\u201d. Folios 135 y 136, cuaderno uno. \u00a0<\/p>\n<p>16 Las asignaturas cursadas y aprobadas en el segundo semestre de 2019 fueron producci\u00f3n av\u00edcola (3.6) y salud p\u00fablica (3.0), seg\u00fan el certificado No. 5984 del 20 de agosto de 2020, expedido por la Directora de admisiones, registro y control acad\u00e9mico de la UTP, allegado en sede de revisi\u00f3n.\u00a0 \u00a0<\/p>\n<p>17 Las asignaturas cursadas y aprobadas en el primer semestre de 2020 fueron biolog\u00eda celular y molecular (4.1), fisiolog\u00eda de la reproducci\u00f3n (3.0), medicina interna de grandes animales (3.8) y trabajo de grado (5.0), seg\u00fan el certificado No. 6012 del 20 de agosto de 2020, expedido por la Directora de admisiones, registro y control acad\u00e9mico de la UTP, allegado en sede de revisi\u00f3n. \u00a0<\/p>\n<p>18 Las asignaturas matriculadas para el segundo semestre de 2020 son bioqu\u00edmica aplicada, fisiolog\u00eda general, medicina interna de peque\u00f1os animales, gen\u00e9tica y mejoramiento animal y cirug\u00eda II, seg\u00fan el certificado No. 5987 del 20 de agosto de 2020, expedido por la Directora de admisiones, registro y control acad\u00e9mico de la UTP, allegado en sede de revisi\u00f3n. \u00a0<\/p>\n<p>19 A pesar de las m\u00faltiples solicitudes formuladas en el escrito de tutela, la agente oficiosa las sintetiz\u00f3 en estas dos pretensiones en la declaraci\u00f3n de parte rendida ante el Juzgado Quinto Laboral del Circuito de Pereira, el 23 de agosto de 2013. Folios 56 y 57, cuaderno uno. Igualmente, la estudiante Catalina Celis Rivera ratific\u00f3 dichas peticiones en la declaraci\u00f3n de parte rendida ante el Juzgado Quinto Laboral del Circuito de Pereira, el 24 de julio de 2020, en cumplimiento de la comisi\u00f3n ordenada por esta Corporaci\u00f3n en sede de revisi\u00f3n.\u00a0 \u00a0<\/p>\n<p>20 El contenido espec\u00edfico de estos componentes en la \u201cPropuesta Acompa\u00f1amiento a Catalina Celis Rivera Desde la Universidad Tecnol\u00f3gica de Pereira y la Vicerrector\u00eda de Responsabilidad Social y Bienestar Universitario\u201d es el siguiente: \u201c- Se brindar\u00e1 formaci\u00f3n y asesor\u00eda, a los docentes del programa acad\u00e9mico de Veterinaria sobre la discapacidad que posee la estudiante, las caracter\u00edsticas propias y estrategias pedag\u00f3gicas para que acceda con mayor facilidad a los nuevos aprendizajes. (se contar[\u00e1] con la profesional en Fonoaudiolog\u00eda y Magister en Educaci\u00f3n Martha Luc\u00eda Garz\u00f3n, adscrita a la Maestr\u00eda de Educaci\u00f3n e Inclusi\u00f3n). \/\/ &#8211; Se le asign\u00f3 como monitora permanente de apoyo a estudios, lecturas y trabajos a la estudiante del programa de Medicina Veterinaria y Zootecnia (\u2026). \/\/ &#8211; A partir del segundo semestre acad\u00e9mico del a\u00f1o 2016, se contar[\u00e1] con dos estudiantes del programa de Lic. En Pedagog\u00eda Infantil, las cuales se han desempe\u00f1ado como monitoras acad\u00e9micas de la materia Necesidades Educativas Especiales (\u2026), las cuales contar[\u00e1]n con la supervisi\u00f3n de la docente Martha Luc\u00eda Garz\u00f3n, experta en el tema, ellas ofrecer\u00e1n un acompa\u00f1amiento permanente con respecto a la utilizaci\u00f3n de estrategias y medios requeridos para potenciar las habilidades intelectuales que la estudiante debe fortalecer y reforzar. \/\/ &#8211; Despu\u00e9s de la formaci\u00f3n que se le ofrecer\u00e1 a docentes y directivos, se espera contar con la sensibilizaci\u00f3n y el abordaje adecuado de la discapacidad con la que cuenta la estudiante, haciendo \u00e9nfasis y garantizando que (sic) un curr\u00edculo y m\u00e9todos de evaluaci\u00f3n diferencial, manejo de horarios y tiempos extendidos para tareas y trabajos. Con el objetivo de tener en cuenta su estilo de aprendizaje, fortalezas y la utilizaci\u00f3n de herramientas que le permitan demostrar sus competencias\u201d. \u00a0<\/p>\n<p>21 \u201cPor medio de la cual se establecen las disposiciones para garantizar el pleno ejercicio de los derechos de las personas con discapacidad\u201d. \u00a0<\/p>\n<p>22 \u201cPor el cual se reglamenta en el marco de la educaci\u00f3n inclusiva la atenci\u00f3n educativa a la poblaci\u00f3n con discapacidad\u201d. \u00a0<\/p>\n<p>23 Particularmente, las Sentencias T-551 de 2011, T-097 de 2016 y T-027 de 2018, en lo que hace referencia al derecho a la educaci\u00f3n superior de las personas con discapacidad y al alcance y los l\u00edmites del derecho a la autonom\u00eda universitaria. \u00a0<\/p>\n<p>24 Folio 5, cuaderno uno. \u00a0<\/p>\n<p>25 Folios 9 y 10, cuaderno uno. \u00a0<\/p>\n<p>26 Folios 60 y 61, cuaderno uno. \u00a0<\/p>\n<p>27 Folio 61, cuaderno uno.\u00a0 \u00a0<\/p>\n<p>28 Espec\u00edficamente el Tribunal sostuvo: \u201c[\u2026] es menester se\u00f1alar que la presente acci\u00f3n de tutela no ser\u00eda el foro indicado para dilucidar en torno a la oportunidad, ni la idoneidad o no de la persona elegida como monitora, puesto que tales materias ser\u00edan propias del incidente de desacato en el marco de la acci\u00f3n de tutela propuesta anteriormente [\u2026]\u201d. Folio 13, cuaderno dos. \u00a0<\/p>\n<p>29 Al respecto, relat\u00f3 que se gradu\u00f3 de bachiller del instituto Comfamiliar en el que curs\u00f3 los grados 10\u00ba y 11\u00ba en la modalidad semestralizada, durante tres a\u00f1os. Afirm\u00f3 que parte de los apoyos brindados por la instituci\u00f3n consist\u00edan en que cuando no entend\u00eda algo, ella se dirig\u00eda al profesor directamente, quien se dedicaba a explicarle con exclusividad. \u00a0\u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>30 Sentencia T-010 de 1992. \u00a0<\/p>\n<p>31 Al respecto, pueden consultarse, entre otras, las Sentencias T-727 de 2011, T-1233 de 2008 y T-568 de 2006. \u00a0<\/p>\n<p>32 Sentencia T-1103 de 2005, entre otras. \u00a0<\/p>\n<p>33 Ibidem. \u00a0<\/p>\n<p>34 Ver, entre otras, las Sentencias T-1103 de 2005, T-1022 de 2006, y T-1233 de 2008. \u00a0<\/p>\n<p>35 Sentencia T-560 de 2009. \u00a0<\/p>\n<p>36 Al respecto, pueden consultarse, entre otras, las Sentencias T-593 de 2002, T-502 de 2003 y T-184 de 2005. \u00a0<\/p>\n<p>37 Sentencia T-1103 de 2005.\u00a0 \u00a0<\/p>\n<p>39 SU-1219 de 2001. \u00a0<\/p>\n<p>40 Sentencias T-185 de 2005, T-502 de 2008, y T-185 de 2013.\u00a0 \u00a0<\/p>\n<p>41 Sentencia SE-627 de 2015. \u00a0<\/p>\n<p>42 Anexo en digital dentro del expediente, CD folio 59, cuaderno uno. \u00a0<\/p>\n<p>43 Radicado en primera instancia No. 2016-015. Folios 171 a 182, cuaderno uno. \u00a0<\/p>\n<p>44 Copia simple de las actuaciones surtidas en el tr\u00e1mite de tutela radicado No. 2016-015, cuaderno de revisi\u00f3n. \u00a0<\/p>\n<p>45 Sentencia T-1103 de 2005.\u00a0 \u00a0<\/p>\n<p>46 \u201cArt\u00edculo 12. Igual reconocimiento como persona ante la ley. \/\/ 1. Los Estados Partes reafirman que las personas con discapacidad tienen derecho en todas partes al reconocimiento de su personalidad jur\u00eddica. \/\/ 2. Los Estados Partes reconocer\u00e1n que las personas con discapacidad tienen capacidad jur\u00eddica en igualdad de condiciones con las dem\u00e1s en todos los aspectos de la vida. \/\/ 3. Los Estados Partes adoptar\u00e1n las medidas pertinentes para proporcionar acceso a las personas con discapacidad al apoyo que puedan necesitar en el ejercicio de su capacidad jur\u00eddica. \/\/ 4. Los Estados Partes asegurar\u00e1n que en todas las medidas relativas al ejercicio de la capacidad jur\u00eddica se proporcionen salvaguardias adecuadas y efectivas para impedir los abusos de conformidad con el derecho internacional en materia de derechos humanos. Esas salvaguardias asegurar\u00e1n que las medidas relativas al ejercicio de la capacidad jur\u00eddica respeten los derechos, la voluntad y las preferencias de la persona, que no haya conflicto de intereses ni influencia indebida, que sean proporcionales y adaptadas a las circunstancias de la persona, que se apliquen en el plazo m\u00e1s corto posible y que est\u00e9n sujetas a ex\u00e1menes peri\u00f3dicos por parte de una autoridad o un \u00f3rgano judicial competente, independiente e imparcial. Las salvaguardias ser\u00e1n proporcionales al grado en que dichas medidas afecten a los derechos e intereses de las personas. \/\/ 5. Sin perjuicio de lo dispuesto en el presente art\u00edculo, los Estados Partes tomar\u00e1n todas las medidas que sean pertinentes y efectivas para garantizar el derecho de las personas con discapacidad, en igualdad de condiciones con las dem\u00e1s, a ser propietarias y heredar bienes, controlar sus propios asuntos econ\u00f3micos y tener acceso en igualdad de condiciones a pr\u00e9stamos bancarios, hipotecas y otras modalidades de cr\u00e9dito financiero, y velar\u00e1n por que las personas con discapacidad no sean privadas de sus bienes de manera arbitraria\u201d.\u00a0 \u00a0<\/p>\n<p>47 M.P. Luis Guillermo Guerrero P\u00e9rez. \u00a0<\/p>\n<p>48 Sobre el particular, en la Sentencia T-1001 de 2006 se expuso: \u201cla legitimaci\u00f3n en la causa como requisito de procedibilidad exige la presencia de un nexo de causalidad entre la vulneraci\u00f3n de los derechos del demandante y la acci\u00f3n u omisi\u00f3n de la autoridad o el particular demandado, v\u00ednculo sin el cual la tutela se torna improcedente (\u2026)\u201d. \u00a0<\/p>\n<p>49 La solicitud se present\u00f3 el 18 de julio de 2019. \u00a0<\/p>\n<p>50 La respuesta se dio el primero de agosto de 2019. \u00a0<\/p>\n<p>51 V\u00e9anse, entre otras, las Sentencias T-336 de 2009, T-436 de 2009, T-785 de 2009, T-799 de 2009, T-130 de 2010 y T-136 de 2010. \u00a0<\/p>\n<p>52 V\u00e9anse, adem\u00e1s, las Sentencias T-287 de 1995, T-384 de 1998, T-554 de 1998, SU-086 de 1999, T-716 de 1999, T-156 de 2000, T-418 de 2000, T-815 de 2000, SU-1052 de 2000, T-482 de 2001, T-1062 de 2001, T-135 de 2002, T-500 de 2002 y T-179 de 2003.\u00a0 \u00a0<\/p>\n<p>53 V\u00e9ase, entre otras, las Sentencias T-106 de 1993 y T-100 de 1994. \u00a0<\/p>\n<p>54 Sentencia T-705 de 2012. \u00a0<\/p>\n<p>55 Sobre la procedencia de la acci\u00f3n de tutela cuando se afecta la continuidad en el proceso educativo se pueden consultar las sentencias T-437 de 2005, T-129 de 2016 y T-091 de 2019. \u00a0<\/p>\n<p>56 Sentencia T-763 de 2006, reiterada en la Sentencia T-832 de 2011. \u00a0<\/p>\n<p>57 La norma en cita establece que: \u201cArt\u00edculo 138. Nulidad y restablecimiento del derecho. Toda persona que se crea lesionada en un derecho subjetivo amparado en una norma jur\u00eddica, podr\u00e1 pedir que se declare la nulidad del acto administrativo particular, expreso o presunto, y se le restablezca el derecho; tambi\u00e9n podr\u00e1 solicitar que se le repare el da\u00f1o. La nulidad proceder\u00e1 por las mismas causales establecidas en el inciso segundo del art\u00edculo anterior. Igualmente podr\u00e1 pretenderse la nulidad del acto administrativo general y pedirse el restablecimiento del derecho directamente violado por este al particular demandante o la reparaci\u00f3n del da\u00f1o causado a dicho particular por el mismo, siempre y cuando la demanda se presente en tiempo, esto es, dentro de los cuatro (4) meses siguientes a su publicaci\u00f3n. Si existe un acto intermedio, de ejecuci\u00f3n o cumplimiento del acto general, el t\u00e9rmino anterior se contar\u00e1 a partir de la notificaci\u00f3n de aquel\u201d. \u00a0<\/p>\n<p>58 Art\u00edculo 137 de la Ley 1437 de 2011. \u00a0<\/p>\n<p>59 Sobre el hecho sobreviniente se pueden consultar, entre otras, las Sentencias T-155 de 2017, T-265 de 2017, T-457 de 2017, T-472 de 2017, T-543 de 2017, T-106 de 2018, T-310 de 2018, T-467 de 2018, T-004 de 2019, T-005 de 2019 y T-038 de 2019.\u00a0 \u00a0<\/p>\n<p>60 Informe allegado por requerimiento de esta Sala de Revisi\u00f3n, el 21 de agosto de 2020.\u00a0 \u00a0<\/p>\n<p>61 Las asignaturas cursadas y aprobadas en el segundo semestre de 2019 fueron producci\u00f3n av\u00edcola (3.6) y salud p\u00fablica (3.0), seg\u00fan el certificado No. 5984 del 20 de agosto de 2020, expedido por la Directora de admisiones, registro y control acad\u00e9mico de la UTP, allegado en sede de revisi\u00f3n.\u00a0 \u00a0<\/p>\n<p>62 Folios 135 a 137, cuaderno uno. \u00a0<\/p>\n<p>63 Las asignaturas cursadas y aprobadas en el primer semestre de 2020 fueron biolog\u00eda celular y molecular (4.1), fisiolog\u00eda de la reproducci\u00f3n (3.0), medicina interna de grandes animales (3.8) y trabajo de grado (5.0), seg\u00fan el certificado No. 6012 del 20 de agosto de 2020, expedido por la Directora de admisiones, registro y control acad\u00e9mico de la UTP, allegado en sede de revisi\u00f3n. \u00a0<\/p>\n<p>64 Las asignaturas matriculadas para el segundo semestre de 2020 son bioqu\u00edmica aplicada, fisiolog\u00eda general, medicina interna de peque\u00f1os animales, gen\u00e9tica y mejoramiento animal y cirug\u00eda II, seg\u00fan el certificado No. 5987 del 20 de agosto de 2020, expedido por la Directora de admisiones, registro y control acad\u00e9mico de la UTP, allegado en sede de revisi\u00f3n. \u00a0<\/p>\n<p>65 Sentencia T-097 de 2016. \u00a0<\/p>\n<p>66 Sentencia T-743 de 2013. \u00a0<\/p>\n<p>67 Sentencia T-850 de 2014. \u00a0<\/p>\n<p>68 Sentencia T-850 de 2014. \u00a0<\/p>\n<p>69 Sentencia T-476 de 2015. \u00a0<\/p>\n<p>70 Convenci\u00f3n Interamericana para la Eliminaci\u00f3n de todas las formas de discriminaci\u00f3n contra la Personas con Discapacidad. \u00a0<\/p>\n<p>71 Normas Uniformes sobre la Igualdad de Oportunidades para las Personas con Discapacidad. Naciones Unidas, Resoluci\u00f3n 48 de 1996, art. 6. \u00a0<\/p>\n<p>72 Convenci\u00f3n Internacional sobre Derechos de las Personas con Discapacidad, art. 24. \u00a0<\/p>\n<p>74 &#8220;Por el cual se reglamenta la atenci\u00f3n educativa para personas con limitaciones o con capacidades o talentos excepcionales&#8221;. \u00a0<\/p>\n<p>75 \u201cPor la cual se establecen mecanismos de integraci\u00f3n social de las personas con limitaci\u00f3n y se dictan otras disposiciones\u201d. \u00a0<\/p>\n<p>76 \u00a0\u201cPor medio de la cual se establecen las disposiciones para garantizar el pleno ejercicio de los derechos de las personas con discapacidad\u201d: \u00a0<\/p>\n<p>77 Lineamientos Pol\u00edtica de Educaci\u00f3n Superior Inclusiva. Ministerio de Educaci\u00f3n Nacional. Bogot\u00e1, Colombia, 2013. Disponible en: https:\/\/www.mineducacion.gov.co\/1759\/articles-357277_recurso_0.pdf\u00a0 \u00a0<\/p>\n<p>78 Herramienta actualizada en el 2017. Disponible en: https:\/\/www.mineducacion.gov.co\/1759\/articles-357277_recurso_1.pdf\u00a0 \u00a0<\/p>\n<p>79 Ibidem, p. 64-74. \u00a0<\/p>\n<p>80 Ibidem, p. 75-80. \u00a0<\/p>\n<p>81 Documento informal aportado tanto por la parte accionante, folios 22 y 23, cuaderno uno, como por la parte accionada, folios 76 y 77, cuaderno uno. \u00a0<\/p>\n<p>82 El informe presentado del a\u00f1o 2010 refiere paciente con retardo en el desarrollo de los procesos cognitivos b\u00e1sicos y superiores. Folio 108, cuaderno uno.\u00a0 \u00a0<\/p>\n<p>83 Informe de seguimiento caso Catalina Celis Rivera visible a folios 102 a 108, cuaderno uno. \u00a0<\/p>\n<p>84 En sede de revisi\u00f3n, la se\u00f1ora Miriam Rivera Osorio insisti\u00f3 en se\u00f1alar que la situaci\u00f3n econ\u00f3mica de su hogar no ha variado desde el a\u00f1o 2015 cuando la Universidad le realiz\u00f3 el estudio socioecon\u00f3mico para conceder la reducci\u00f3n en el pago del valor de la matr\u00edcula a su hija. Esto quiere decir que tanto ella como su hija se sostienen con los ingresos de la pensi\u00f3n de invalidez que le fue reconocida a la madre, que equivalen a poco m\u00e1s de un salario m\u00ednimo, con los cuales deben pagar arriendo de vivienda as\u00ed como transporte, copagos a citas m\u00e9dicas, medicamentos excluidos del POS y alimentaci\u00f3n vegana para Catalina. \u00a0 \u00a0 \u00a0<\/p>\n<p>85 Folio 26, cuaderno uno. \u00a0<\/p>\n<p>86 Folio 154, cuaderno uno. \u00a0<\/p>\n<p>87 Folio 114, cuaderno uno. \u00a0<\/p>\n<p>88 Folios 112 y 113, cuaderno uno. \u00a0<\/p>\n<p>89 Folios 60 y 61, cuaderno uno. \u00a0<\/p>\n<p>90 Precisamente, uno de los componentes de la propuesta establece que \u201c[s]e requiere de acompa\u00f1amiento permanente y cooparticipativo (sic) Universidad-familia con el fin de implementar estrategias al interior de su n\u00facleo familiar teniendo como objetivo fortalecer las habilidades acad\u00e9micas necesarias para su desempe\u00f1o integral dentro de la UTP\u201d.\u00a0 \u00a0<\/p>\n<p>91 \u00c9nfasis por fuera del texto original.\u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia T-435\/20 \u00a0 \u00a0\u00a0 DERECHO A LA EDUCACION SUPERIOR DE PERSONAS EN SITUACION DE DISCAPACIDAD-Componente de adaptabilidad \u00a0 DERECHO FUNDAMENTAL A LA EDUCACION DE PERSONAS EN SITUACION DE DISCAPACIDAD-Deber del Estado y de las instituciones de educaci\u00f3n superior para garantizar acceso en condiciones de igualdad \u00a0 \u00a0\u00a0 DERECHO A LA EDUCACION SUPERIOR DE [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130],"tags":[],"class_list":["post-27668","post","type-post","status-publish","format-standard","hentry","category-tutelas-2020"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/27668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=27668"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/27668\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=27668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=27668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=27668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}