{"id":27828,"date":"2024-07-02T21:47:29","date_gmt":"2024-07-02T21:47:29","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/07\/02\/c-215-21\/"},"modified":"2024-07-02T21:47:29","modified_gmt":"2024-07-02T21:47:29","slug":"c-215-21","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/c-215-21\/","title":{"rendered":"C-215-21"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Sentencia C-215\/21\u00a0 \u00a0<\/p>\n<p>PRINCIPIO DE UNIDAD DE MATERIA-No vulneraci\u00f3n\/PRINCIPIO DE UNIDAD DE MATERIA-Conexidad tem\u00e1tica \u00a0<\/p>\n<p>(\u2026) este programa de asistencia social a la vejez se encuentra (i) dentro de la tem\u00e1tica que regula el T\u00edtulo VI de la Ley 1328 de 2009, sobre el \u201cR\u00e9gimen Financiero de los Fondos de Pensi\u00f3n Obligatoria y Cesant\u00eda\u201d, relativa a aspectos propios de la seguridad social y del sistema financiero; y (ii) corresponde a un desarrollo de la materia general de la Ley 1328 de 2009 y del proyecto de ley que le dio fruto, ya que corresponde a \u201cLas actividades financiera, burs\u00e1til, aseguradora y cualquier otra relacionada con el manejo, aprovechamiento e inversi\u00f3n de los recursos de captaci\u00f3n a las que se refiere el literal d) del numeral 19 del art\u00edculo 150\u201d, en los t\u00e9rminos del art\u00edculo 335 de la Constituci\u00f3n y que responde de manera precisa al t\u00edtulo de la referida ley. En consecuencia, para la Sala, el art\u00edculo demandado se vincula de manera objetiva y razonable con la materia tratada en la Ley 1328 de 2009, y, por lo tanto, no desconoce el principio de unidad de materia prescrito en los art\u00edculos 158 y 169 de la Constituci\u00f3n. \u00a0<\/p>\n<p>DEMANDA DE INCONSTITUCIONALIDAD POR VULNERACION DEL PRINCIPIO DE UNIDAD DE MATERIA-Criterios para la formulaci\u00f3n de un cargo \u00a0<\/p>\n<p>DEMANDA DE INCONSTITUCIONALIDAD POR VULNERACION DEL PRINCIPIO DE PROGRESIVIDAD-Exigencias argumentativas \u00a0<\/p>\n<p>INHIBICION DE LA CORTE CONSTITUCIONAL-Incumplimiento de requisitos exigidos en cargo por violaci\u00f3n al principio de progresividad\u00a0 \u00a0<\/p>\n<p>PRINCIPIO DE UNIDAD DE MATERIA-Contenido y alcance\/PRINCIPIO DE UNIDAD DE MATERIA-Finalidad \u00a0<\/p>\n<p>PRINCIPIO DE UNIDAD DE MATERIA-Instrumento de racionalizaci\u00f3n y tecnificaci\u00f3n del proceso legislativo\/UNIDAD DE MATERIA-Garantiza la transparencia y coherencia del proceso legislativo \u00a0<\/p>\n<p>De esta manera, los arts. 158 y 169 de la Constituci\u00f3n incorporan un instrumento de transparencia, racionalidad y tecnificaci\u00f3n de la actividad legislativa que se materializa en la coherencia interna de las leyes, de manera tal que sus disposiciones est\u00e9n directamente relacionadas con un mismo n\u00facleo tem\u00e1tico y sean fruto de la deliberaci\u00f3n p\u00fablica. Este instrumento garantiza una deliberaci\u00f3n democr\u00e1tica, informada y transparente, que pretendidamente busca repercutir en cuerpos normativos coherentes y arm\u00f3nicos, que garanticen su eficacia. El \u00e1mbito de transparencia de esta exigencia constitucional tiende a evitar que durante cualquier etapa del procedimiento legislativo se les d\u00e9 tr\u00e1mite a disposiciones respecto de las cuales no se observa una conexi\u00f3n unitaria entre los temas que se someten al proceso legislativo y se profieran normas sobre las cuales no se ha surtido el debate democr\u00e1tico del cual debe nacer toda disposici\u00f3n como manifestaci\u00f3n de la voluntad plural. Por su parte, la perspectiva de la racionalizaci\u00f3n de los procesos legislativos de cara a la exigencia de coherencia material tiene como finalidad que los debates que se surtan en el Congreso de la Rep\u00fablica, como foro natural de representaci\u00f3n democr\u00e1tica, se concentren en materias que hayan sido objeto de un proceso deliberativo propio de la reflexi\u00f3n y an\u00e1lisis democr\u00e1tico. Sin duda, la dispersi\u00f3n, la incongruencia y la incoherencia tem\u00e1tica constituyen un obst\u00e1culo a este objetivo, motivo por el cual el constituyente dispuso que los contenidos de un mismo cuerpo normativo deban enmarcarse en una misma materia.\u00a0 \u00a0<\/p>\n<p>PRINCIPIO DE UNIDAD DE MATERIA-Conexidad causal, teleol\u00f3gica, tem\u00e1tica o sistem\u00e1tica \u00a0<\/p>\n<p>CONTROL DE CONSTITUCIONALIDAD POR VULNERACION DEL PRINCIPIO DE UNIDAD DE MATERIA-Metodolog\u00eda\/JUICIO POR VIOLACION DE LA UNIDAD DE MATERIA EN LA ACTIVIDAD LEGISLATIVA-Criterios orientadores\/JUICIO DE UNIDAD DE MATERIA-Niveles de rigor \u00a0<\/p>\n<p>Referencia: Expediente D-14.005 \u00a0<\/p>\n<p>Demanda de inconstitucionalidad contra el art\u00edculo 87 de la Ley 1328 de 2009, \u201cPor la cual se dictan normas en materia financiera, de seguros, del mercado de valores y otras disposiciones\u201d \u00a0<\/p>\n<p>Demandante: \u00a0<\/p>\n<p>Elson Rafael Rodrigo Rodr\u00edguez Beltr\u00e1n \u00a0<\/p>\n<p>Magistrado sustanciador: \u00a0<\/p>\n<p>ANTONIO JOS\u00c9 LIZARAZO OCAMPO \u00a0<\/p>\n<p>Bogot\u00e1 D.C., ocho (8) de julio de dos mil veintiuno (2021) \u00a0<\/p>\n<p>La Corte Constitucional, en ejercicio de sus competencias, en especial de la prevista en el art. 241.4 de la Constituci\u00f3n, y cumplidos los tr\u00e1mites y requisitos previstos en el Decreto 2067 de 19911, decide sobre la demanda de inconstitucionalidad de la referencia, presentada por el ciudadano Elson Rafael Rodrigo Rodr\u00edguez Beltr\u00e1n en ejercicio de la acci\u00f3n p\u00fablica consagrada en el art\u00edculo 40.6 de la Constituci\u00f3n. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. DISPOSICI\u00d3N DEMANDADA \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Art\u00edculo 87 de la Ley 1328 de 2009, \u201cPor la cual se dictan normas en materia financiera, de seguros, del mercado de valores y otras disposiciones\u201d, publicada en el Diario Oficial No. 47.411 de 15 de julio de 2009: \u00a0 \u00a0<\/p>\n<p>\u201cArt\u00edculo 87. Beneficios Econ\u00f3micos Peri\u00f3dicos. Las personas de escasos recursos que hayan realizado aportes o ahorros peri\u00f3dicos o espor\u00e1dicos a trav\u00e9s del medio o mecanismo de ahorro determinados por el Gobierno Nacional, incluidas aquellas de las que trata el art\u00edculo 40 de la Ley 1151 de 2007 podr\u00e1n recibir beneficios econ\u00f3micos peri\u00f3dicos inferiores al salario m\u00ednimo, de los previstos en el Acto legislativo 01 de 2005, como parte de los servicios sociales complementarios, una vez cumplan con los siguientes requisitos: \u00a0<\/p>\n<p>1. Que hayan cumplido la edad de pensi\u00f3n prevista por el R\u00e9gimen de Prima Media del Sistema General de Pensiones. \u00a0<\/p>\n<p>2. Que el monto de los recursos ahorrados m\u00e1s el valor de los aportes obligatorios, m\u00e1s los aportes voluntarios al Fondo de Pensiones Obligatorio y otros autorizados por el Gobierno Nacional para el mismo prop\u00f3sito, no sean suficientes para obtener una pensi\u00f3n m\u00ednima. \u00a0<\/p>\n<p>3. Que el monto anual del ahorro sea inferior al aporte m\u00ednimo anual se\u00f1alado para el Sistema General de Pensiones. \u00a0<\/p>\n<p>Par\u00e1grafo. Para estimular dicho ahorro a largo plazo el Gobierno Nacional, con cargo a los recursos del Fondo de Solidaridad Pensional y teniendo en cuenta las disponibilidades del mismo, podr\u00e1 establecer incentivos que se hagan efectivos al finalizar el per\u00edodo de acumulaci\u00f3n denominados peri\u00f3dicos que guardar\u00e1n relaci\u00f3n con el ahorro individual, con la fidelidad al programa y con el monto ahorrado e incentivos denominados puntuales y\/o aleatorios para quienes ahorren en los per\u00edodos respectivos. \u00a0<\/p>\n<p>En todo caso, el valor total de los incentivos peri\u00f3dicos m\u00e1s los denominados puntuales que se otorguen no podr\u00e1n ser superiores al 50% de la totalidad de los recursos que se hayan acumulado en este programa, de conformidad con la reglamentaci\u00f3n que expida el Gobierno Nacional. \u00a0<\/p>\n<p>Los incentivos que se definir\u00e1n mediante los instructivos de operaci\u00f3n del Programa Social Complementario, denominado Beneficios Econ\u00f3micos Peri\u00f3dicos, deben estar orientados a fomentar tanto la fidelidad como la cultura del ahorro para la vejez. \u00a0<\/p>\n<p>Como mecanismo adicional para fomentar la fidelidad y la cultura del ahorro el Gobierno determinar\u00e1 las condiciones en las cuales los recursos ahorrados podr\u00e1n ser utilizados como garant\u00eda para la obtenci\u00f3n de cr\u00e9ditos relacionados con la atenci\u00f3n de imprevistos del ahorrador o de su grupo familiar, de conformidad con la reglamentaci\u00f3n que se expida para tal efecto. \u00a0<\/p>\n<p>Tambi\u00e9n se podr\u00e1 crear como parte de los incentivos la contrataci\u00f3n de seguros que cubran los riesgos de invalidez y muerte del ahorrador, cuya prima ser\u00e1 asumida por el Fondo de Riesgos Profesionales. El pago del siniestro se har\u00e1 efectivo mediante una suma \u00fanica. \u00a0<\/p>\n<p>Los recursos acumulados por los ahorradores de este programa constituyen captaciones de recursos del p\u00fablico; por tanto, el mecanismo de ahorro al que se hace referencia en este art\u00edculo ser\u00e1 administrado por las entidades autorizadas y vigiladas por la Superintendencia Financiera de Colombia. \u00a0<\/p>\n<p>El Gobierno Nacional podr\u00e1 establecer el mecanismo de administraci\u00f3n de este ahorro, teniendo en cuenta criterios de eficiencia, rentabilidad y los beneficios que podr\u00edan lograrse como resultado de un proceso competitivo que tambi\u00e9n incentive la fidelidad y la cultura de ahorro de las personas a las que hace referencia este art\u00edculo. \u00a0<\/p>\n<p>Con las sumas ahorradas, sus rendimientos, el monto del incentivo obtenido y la indemnizaci\u00f3n del Seguro, cuando a ella haya lugar, el ahorrador podr\u00e1 contratar un seguro que le pague el Beneficio Econ\u00f3mico Peri\u00f3dico o pagar total o parcialmente un inmueble de su propiedad. \u00a0<\/p>\n<p>Todo lo anterior de conformidad con el reglamento que para el efecto adopte el Gobierno Nacional, siguiendo las recomendaciones del Conpes Social\u201d. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. DEMANDA Y CARGOS \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El demandante solicita la declaratoria de inexequibilidad del citado art\u00edculo, por considerarlo contrario a los arts. 4, 48, 149, 158 y 169 de la Constituci\u00f3n, con fundamento en los cuales formul\u00f3 dos cargos de inconstitucionalidad: (i) violaci\u00f3n del principio de unidad de materia \u2013arts. 4, 149, 158 y 169\u2013 y (ii) violaci\u00f3n del principio de progresividad de la seguridad social \u2013art. 48\u2013.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Presunta violaci\u00f3n del principio de unidad de materia. Para el demandante, la disposici\u00f3n desconoce el principio de unidad de materia pues, al regular asuntos relacionados con el derecho a la seguridad social, este elemento no se encuentra alineado con el eje central de la materia desarrollada en la Ley 1328 de 2009. En su criterio, la disposici\u00f3n desdibuja la coherencia tem\u00e1tica de la ley y no guarda una correspondencia l\u00f3gica con la materia general tratada en ella referida al sector financiero, asegurador y del mercado de valores. En particular, precisa que el art\u00edculo demandado (i) no se compagina con el t\u00edtulo de la ley; (ii) sus elementos se encuentran desconectados del contenido mayoritario de esta, y (iii) no tiene relaci\u00f3n con los prop\u00f3sitos del Gobierno al presentar el proyecto de ley dio lugar a la disposici\u00f3n acusada. El anterior razonamiento lo fundamenta en las siguientes premisas: \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En primer lugar, resalta que el proyecto de ley presentado por el Gobierno nacional no inclu\u00eda la disposici\u00f3n demandada.\u00a0 \u00a0\u00a0<\/p>\n<p>2. En segundo lugar, se\u00f1ala que el objetivo del proyecto de ley difiere de aquel buscado por la medida legislativa acusada. A partir de la trascripci\u00f3n de diversos apartes de la exposici\u00f3n de motivos y de la ponencia para primer debate en la cual se desarrolla el pliego de modificaciones a la iniciativa legislativa explica lo siguiente:\u00a0 \u00a0 \u00a0<\/p>\n<p>\u201cEl objetivo del proyecto 282 de 2008 C\u00e1mara de Representantes, 286 de 2008 Senado es decretar una reforma financiera como qued\u00f3 plasmado en la norma que termin\u00f3 siendo la ley 1328 de 2009, mientras que el prop\u00f3sito de la disposici\u00f3n que concluy\u00f3 en el art\u00edculo demandado es incorporar a un alto porcentaje de la poblaci\u00f3n a los mecanismos estatales de protecci\u00f3n social\u201d. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En tercer lugar, advierte que la materia desarrollada por el art. 87 no se relaciona con el t\u00edtulo de la ley ya que no regula aspectos financieros, de seguros y del mercado de valores, sino \u201cun asunto relacionado con el derecho a la seguridad social, los BEPS, que no corresponde al contenido central de la ley 1328 que es dictar disposiciones dirigidas al sector financiero\u201d2.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En cuarto lugar, para el demandante, el art. 87 \u201cest\u00e1 completamente desconectado y sin ninguna relaci\u00f3n con el resto de la normatividad de la Ley 1328 de 2009, que reform\u00f3 el sistema financiero, como se indica desde el t\u00edtulo de la ley y es reafirmado con el contenido de cada una de las disposiciones que tratan exclusivamente de asuntos financieros y no de aspectos relacionados con el derecho irrenunciable a la seguridad social\u201d3. Al respecto, manifiesta que el tema central de la ley se encuentra determinado por su relaci\u00f3n con el sector financiero, asegurador o del mercado de valores y que el art\u00edculo acusado no se relaciona con aquellos asuntos desarrollados dentro de los diferentes t\u00edtulos, cap\u00edtulos y art\u00edculos que la integran. En consecuencia, echa de menos una relaci\u00f3n de conexidad interna del art\u00edculo con los dem\u00e1s componentes de la ley y, por tanto, concluye que la disposici\u00f3n rompe con la coherencia tem\u00e1tica y correspondencia l\u00f3gica de esta. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Finalmente, indica que la norma acusada \u201ccarece de conexidad causal, teleol\u00f3gica, tem\u00e1tica o sistem\u00e1tica con la materia dominante de la ley 1328 y con su articulado\u201d4. Para sustentar esta afirmaci\u00f3n, aduce que \u201clas razones que dieron origen a la norma 1328 fueron decretar una reforma financiera para adecuar algunos aspectos del modelo del sistema financiero y reorganizar, modernizar, y adecuar el marco regulatorio e institucional\u201d; en ese sentido, sostiene que no se cumplen estos requisitos por cuanto la norma \u201cno adec\u00faa el marco regulatorio e institucional o aspectos del modelo financiero sino que desarrolla una norma constitucional relacionada con el derecho a la seguridad social\u201d5. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Presunta violaci\u00f3n del principio de progresividad de la seguridad social. Tras realizar una exposici\u00f3n del contenido del principio de progresividad y delimitar su alcance frente a la seguridad social en diferentes instrumentos internacionales, el demandante lo define \u201ccomo el criterio de avance paulatino en el establecimiento de las condiciones necesarias para garantizar el ejercicio de un derecho econ\u00f3mico, social o cultural\u201d6. A partir de este, en su concepto, el precepto acusado desconoce el referido principio por lo siguiente: \u00a0 \u00a0<\/p>\n<p>\u201cen lugar de avanzar ampliando progresivamente la cobertura de la seguridad social como lo ordenan las disposiciones citadas, despoja y excluye a grupos vulnerables de personas del derecho a la seguridad social al exigirles para acceder a los BEPS requisitos que no aparecen en el AL 01 de 2005 ni en el t\u00edtulo IV de la ley 100, art\u00edculos 257, 258, 259 y 260 que establecen la \u2018prestaci\u00f3n especial para la vejez\u2019, constituy\u00e9ndose en una disposici\u00f3n regresiva y que prima facie es inconstitucional\u201d7. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. As\u00ed, advierte que la norma es \u201cregresiva e injusta\u201d8 pues retrocede \u201cfrente al nivel de protecci\u00f3n al que han llegado miles de personas vulnerables por su condici\u00f3n econ\u00f3mica porque les cierra las puertas para acceder a los BEPS si no hacen ahorros o aportes peri\u00f3dicos o espor\u00e1dicos\u201d9. \u00a0 \u00a0<\/p>\n<p>Considera que este grupo de personas vulnerables bajo el amparo del citado art. 257 de la Ley 100 de 1993 \u201chan alcanzado un escaso nivel de mayor protecci\u00f3n que el reglado en el art\u00edculo demandado\u201d10 y que el \u201csistema de protecci\u00f3n social dise\u00f1ado en el art\u00edculo 1 de la Ley 789 de 2002\u201d11 se ha visto afectado por la disposici\u00f3n acusada, motivo por el cual estima que la norma es regresiva. \u00a0<\/p>\n<p>I. INTERVENCIONES Y CONCEPTOS \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. A continuaci\u00f3n, se enuncia el sentido de las intervenciones y del concepto del Procurador General de la Naci\u00f3n. Luego, se describen las razones que fundamentan cada postura: \u00a0 \u00a0<\/p>\n<p>Exequibilidad \u00a0\u00a0<\/p>\n<p>Ministerio del Trabajo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Administradora Colombiana de Pensiones \u2013 Colpensiones \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Departamento de Derecho Laboral de la Universidad Externado de Colombia \u00a0\u00a0<\/p>\n<p>Ministerio de Hacienda y Cr\u00e9dito P\u00fablico\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Asociaci\u00f3n Nacional de Empresarios de Colombia \u2013 ANDI \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Procuradora General de la Naci\u00f3n \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Autoridades que dictaron o participaron en la elaboraci\u00f3n o expedici\u00f3n de las disposiciones demandadas12 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ministerio de Hacienda y Cr\u00e9dito P\u00fablico \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Solicita la declaratoria de exequibilidad de la disposici\u00f3n demandada. El art. 87 no desconoce el principio de unidad de materia, ni el principio de progresividad. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En cuanto al principio de unidad de materia se\u00f1ala lo siguiente:\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Este principio precisa de una interpretaci\u00f3n acorde con el amplio margen de configuraci\u00f3n del legislador en la respectiva materia y con el principio democr\u00e1tico, por lo que esta no debe ser r\u00edgida o estricta13. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Igualmente, afirma que la norma respeta el criterio de conexidad sistem\u00e1tica, toda vez que \u201clos BEPS son un instrumento financiero de ahorro para la vejez [p]or tanto, como instrumento financiero, fue susceptible del desarrollo que la Ley 1328 impuls\u00f3 al dictar normas financieras y \u2018disposiciones que contemplen medidas e instrumentos especiales de protecci\u00f3n\u2019, conforme se consign\u00f3 en el art\u00edculo 1 de dicha Ley\u201d. De esta forma, su relaci\u00f3n con las dem\u00e1s disposiciones est\u00e1 dada al constituir un producto financiero que se encuentra bajo la administraci\u00f3n de una entidad financiera, vigilada por la Superintendencia Financiera de Colombia. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Finalmente, la medida cumple con el criterio de conexidad tem\u00e1tica, ya que, \u201csi est\u00e1 probado que los beneficios econ\u00f3micos peri\u00f3dicos constituyen captaciones de recursos del p\u00fablico y que estos recursos son administrados por una entidad de naturaleza financiera y se encuentran vigilados por la Superintendencia Financiera de Colombia, es claro que los BEPS est\u00e1n \u00edntimamente relacionados y conectados con el Sistema Financiero y, en consecuencia, al contenido b\u00e1sico del ordenamiento legal que se est\u00e1 examinando\u201d17. Adem\u00e1s, advierte que \u201cla exposici\u00f3n de motivos de la iniciativa legislativa y el texto final de la Ley 1328 de 2009 abordan temas directamente relacionados con el Sistema de Protecci\u00f3n a la Vejez\u201d18, motivo por el cual afirma que \u201cse equivoca el demandante al aducir que, por estar los Beneficios Econ\u00f3micos Peri\u00f3dicos relacionados con el desarrollo de la Seguridad Social, no tienen un componente financiero y por ende no pod\u00edan ser incluidos mediante una norma relativa al sistema financiero\u201d19. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ahora, en cuanto a la presunta violaci\u00f3n del principio de progresividad, el Ministerio de Hacienda explica que la norma materializa el mandato del constituyente, contenido en el Acto Legislativo 01 de 2005, que otorga un amplio margen de configuraci\u00f3n para determinar los casos en los que procede el otorgamiento de beneficios econ\u00f3micos peri\u00f3dicos a personas de escasos recursos, que no cumplen con las condiciones necesarias para tener derecho a una pensi\u00f3n. De esta forma, la disposici\u00f3n demandada ampl\u00eda la cobertura del Sistema de Seguridad Social a un \u00e1rea en la que anteriormente un grupo de personas se encontraba desprovisto de cualquier protecci\u00f3n social. En este sentido, resalta lo siguiente: \u00a0 \u00a0<\/p>\n<p>\u201cel art\u00edculo 87 demandado desarroll\u00f3 un mecanismo progresivo, pues a trav\u00e9s de este se ampl\u00eda la cobertura del sistema en general, al permitir que mediante un ahorro, personas de bajos de recursos, que no logran cumplir con los requisitos de acceso a la pensi\u00f3n, logren obtener unos recursos que son completados por el Estado a trav\u00e9s del subsidio del 20%, auspiciando la independencia econ\u00f3mica en sus beneficiarios, toda vez que contar\u00e1n con un ingreso por el resto de su vida, o con unas facilidades para la adquisici\u00f3n de vivienda\u201d.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Entidades p\u00fablicas, organizaciones privadas y expertos invitados20 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ministerio del Trabajo \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Solicita declarar exequible la disposici\u00f3n demandada. A su juicio, en cuanto al cargo por desconocimiento del principio de unidad de materia,\u00a0 \u00a0 \u00a0<\/p>\n<p>\u201cal conllevar el mecanismo BEPS una actividad financiera, como lo es la captaci\u00f3n de ahorros, y que dicha actividad deba ser administrada por una entidad sometida a inspecci\u00f3n y vigilancia de la Superintendencia Financiera de Colombia, su inclusi\u00f3n en la Ley 1328 era m\u00e1s que necesaria y [\u2026 por tanto] no contradice el principio de unidad de materia\u201d21.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Seg\u00fan precisa, los BEPS constituyen un mecanismo de ahorro que involucra la captaci\u00f3n de recursos del p\u00fablico, motivo por el cual no es posible \u201cdesligar\u201d la regulaci\u00f3n de este mecanismo del objeto principal de la Ley 1328 de 2009. En l\u00ednea con lo anterior resalta lo siguiente: \u00a0 \u00a0<\/p>\n<p>\u201ccomo quiera que la Ley 1328 de 2009 implica una reforma del sistema financiero y propende a una protecci\u00f3n a los usuarios de los servicios del sistema, en el que se encuentra la captaci\u00f3n de recursos del p\u00fablico, al estar inmerso el mecanismo de ahorro BEPS en tales servicios, aun siendo parte del Sistema de Seguridad Social, existe unidad del Art\u00edculo 87 con el resto del articulado\u201d22. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Adicionalmente, destaca que existe unidad de materia entre el art\u00edculo acusado y la referida ley, por cuanto, si bien los BEPS son un componente de la Seguridad Social \u201cel T\u00cdTULO IV de la misma Ley se ocupa del R\u00e9gimen Financiero de los Fondos de Pensi\u00f3n Obligatoria, los cuales tambi\u00e9n hacen parte del Sistema General de Seguridad Social\u201d. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En cuanto al segundo cargo, relacionado con el presunto desconocimiento del principio de progresividad, pone de presente que, \u201cla Parte Actora confunde la naturaleza de los Beneficios Econ\u00f3micos Peri\u00f3dicos, con los subsidios para los adultos mayores en condici\u00f3n de pobreza, que ofrece el Programa Colombia Mayor y que consagr\u00f3 el Libro IV de la Ley 100 de 1993\u201d23. As\u00ed, precisa que entre estos programas existen profundas diferencias la cuales delimita de la siguiente forma: \u00a0 \u00a0<\/p>\n<p>\u201cel primero es un mecanismo de ahorro para la poblaci\u00f3n econ\u00f3micamente activa que por sus condiciones laborales no cotiza al Sistema de Seguridad Social en Pensiones, pero que poseen alguna capacidad de ahorro, por lo que se les incentiva a que de manera voluntaria ahorren para que logren un ingreso en la vejez, el cual podr\u00eda alcanzar hasta el 85% del Salario M\u00ednimo Mensual Legal Vigente; en contraposici\u00f3n, el segundo est\u00e1 destinado a las personas adultas mayores que no tienen una red de apoyo y por consiguiente viven en la pobreza, para lo cual deben cumplir unos requisitos y someterse a un proceso de priorizaci\u00f3n y esperar el turno que les corresponda seg\u00fan su grado de vulnerabilidad, para que obtengan un cupo en el Programa y una vez admitidos como beneficiarios, reciban un subsidio de $80.000 pesos mensuales\u201d24. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De esta manera, concluye que resulta equivocado pretender equiparar dichos programas como lo hace el actor puesto que \u201clos grupos poblacionales a los cuales se encuentran dirigidos son absolutamente diferentes, y cumplen objetivos diferentes, pues los BEPS son una alternativa de ahorro para la vejez, mientras Colombia Mayor proporciona un sustento para personas que por su edad y nivel socioecon\u00f3mico, se encuentran en estado de vulnerabilidad\u201d. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Administradora Colombiana de Pensiones \u2013 Colpensiones \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En primer lugar, considera que la demanda no es apta, ya que carece de \u201cclaridad e hilaridad [sic], [por lo que] se impide la debida intelecci\u00f3n de los argumentos del accionante, los cuales, en su gran mayor\u00eda se encuentran inconclusos\u201d25. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En segundo lugar, en caso de que se considere la demanda apta, solicita que se declare exequible la norma demandada. De un lado, precisa que el an\u00e1lisis que adelanta el actor \u201cdesconoce el car\u00e1cter pluridimensional de la seguridad social, que prevista bajo la \u00f3ptica del sistema agrupa las obligaciones del Estado y la sociedad, las instituciones, los recursos destinados a garantizar la cobertura de las prestaciones de car\u00e1cter econ\u00f3mico, de salud y servicios complementarios\u201d26.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En esta l\u00ednea, indica que el art\u00edculo demandado no difiere de la regulaci\u00f3n de car\u00e1cter financiero y asegurador de la Ley 1328 de 2009. Se\u00f1ala que: \u201cA diferencia de las obligaciones que devienen del sistema general de pensiones basada en la cotizaci\u00f3n, en los BEPS, uno de los pilares del programa, se encuentra referido a la posibilidad de conformar un ahorro voluntario que cuenta con la caracter\u00edstica de ser flexible en cuant\u00eda y periodicidad\u201d27. En relaci\u00f3n con este \u00faltimo aspecto, destaca algunos componentes que evidencian la afinidad tem\u00e1tica entre la disposici\u00f3n y la materia desarrollada en la ley, as\u00ed:\u00a0 \u00a0 \u00a0<\/p>\n<p>\u201cLos recursos acumulados por los ahorradores de este programa constituyen captaciones de recursos del p\u00fablico; [l]a destinaci\u00f3n de recursos ahorrados en la etapa de desacumulaci\u00f3n, puede tener a trav\u00e9s de la devoluci\u00f3n de los recursos, o de la constituci\u00f3n de una anualidad vitalicia que el ahorrador adquiere con una compa\u00f1\u00eda de seguros legalmente constituida, para que pueda contar con pago peri\u00f3dico; [e]l ahorrador que haya realizado por lo menos seis (6) pagos equivalentes a seis (6) smdlv en el a\u00f1o inmediatamente anterior, podr\u00e1 acceder a incentivos puntuales consistente en un seguro de vida; y Colpensiones, es la entidad a la que se la ha asignado la administraci\u00f3n del Sistema de Ahorro de Beneficios Econ\u00f3micos Peri\u00f3dicos, y justamente por la administraci\u00f3n de este producto ostenta la naturaleza de empresa Industrial y Comercial del Estado organizada como entidad financiera de car\u00e1cter especial, la cual se rige adem\u00e1s de sus propios estatutos y por el Estatuto Org\u00e1nico del Sistema Financiero\u201d28. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. A partir de lo anterior, indica que estos elementos demuestran que la regulaci\u00f3n de los BEPS en el art\u00edculo acusado a pesar de conformar un servicio social complementario no est\u00e1 desprovista de un contenido financiero y asegurador29. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En lo atinente al segundo cargo, el interviniente destaca que el legislador cuenta con un amplio margen de configuraci\u00f3n en materia de seguridad social, especialmente en virtud de lo dispuesto en el Acto Legislativo 01 de 2005. Ante esta situaci\u00f3n, es \u00e9l el llamado a determinar \u201clas condiciones, el grupo poblacional, los requisitos y la cobertura para el acceso a ciertos servicios\u201d30. En consecuencia, sostiene que no parece razonable la interpretaci\u00f3n del demandante bajo la cual todo el conglomerado social deber\u00eda estar cubierto por el programa social de los BEPS. En especial, resalta que el demandante deja de lado el hecho de que los BEPS \u201cse ofrecen como un mecanismo para la protecci\u00f3n para la vejez que hacen parte de los servicios sociales complementarios, independiente del R\u00e9gimen de Prima Media con Prestaci\u00f3n Definida, con la finalidad de que las personas obtengan un ingreso peri\u00f3dico, personal e individual integrado por su ahorro y en la asignaci\u00f3n de un incentivo basado en la fidelidad o adherencia al programa\u201d31. En congruencia con lo anterior, destaca que no es comprensible la acusaci\u00f3n en la medida en que predica una presunta regresividad realizando \u201cun juicio que deviene de la comparaci\u00f3n de presupuestos que emanan de la interpretaci\u00f3n de prestaciones provenientes del Sistema de Seguridad Social en Pensiones\u201d32, que no directamente de la Constituci\u00f3n. As\u00ed las cosas, concluye lo siguiente: \u00a0 \u00a0<\/p>\n<p>\u201cno existe a juicio de esta administradora contrariedad de la norma enjuiciada con el mandato superior cuando en la Ley se determina que el esquema de BEPS es voluntario y flexible en cuant\u00eda y periodicidad, que los incentivos por parte del Estado consideran el esfuerzo de ahorro de cada persona, que se incentiva la fidelidad con el programa, como tampoco en lo que respecta a la obtenci\u00f3n de un beneficio o ingreso de naturaleza peri\u00f3dico una vez se cumplan los requisitos de edad establecidos por la Ley\u201d33.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Asociaci\u00f3n Nacional de Empresarios de Colombia \u2013 ANDI \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Solicita declarar la constitucionalidad de la disposici\u00f3n.\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Precisa que la finalidad de la medida es proteger a la poblaci\u00f3n que normalmente no tiene acceso a mecanismos de protecci\u00f3n en la vejez, \u201ccomo consecuencia de las circunstancias propias del mercado laboral y los niveles de productividad del pa\u00eds\u201d34. \u00a0\u00a0<\/p>\n<p>2. Indica que el mercado laboral colombiano se caracteriza por tener una alta informalidad en la que el \u201c59% de los ocupados se encontraban en el sector informal\u201d35 y que solo el \u201c35.1% tiene cobertura del sistema pensional\u201d. En ese sentido, resalta que la mayor\u00eda de las personas \u201cocupadas\u201d no tiene acceso a la seguridad social. Igualmente, resalta que \u201clos BEPS se han considerado pensiones semicontributivas por lo cual no est\u00e1n sometidas a las reglas del sistema pensional y con las cuales se protegen los derechos fundamentales y principios constitucionales de la poblaci\u00f3n que devengan menos de un (1) SMLMV\u201d36, raz\u00f3n por la cual \u201cno constituyen una pensi\u00f3n ni hacen parte del sistema general de seguridad social, por lo tanto, no deben entenderse como servicio p\u00fablico\u201d37. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Departamento de Derecho Laboral de la Universidad Externado de Colombia38 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La disposici\u00f3n debe ser declarada exequible. Seg\u00fan precisan, \u201clos BEPS son una especie de incentivo de ahorro, captado p\u00fablicamente y dirigido a un p\u00fablico especial, tendiente a asegurar un retorno econ\u00f3mico paliativo futuro a favor de un grupo de poblaci\u00f3n vulnerable incapaz de adquirir una pensi\u00f3n de vejez precisamente por su situaci\u00f3n de debilidad econ\u00f3mica\u201d39. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En ese sentido, se acredita el cumplimiento de las exigencias derivadas del principio de unidad de materia, por cuanto la regulaci\u00f3n constituye el desarrollo por parte del legislador de la facultad consagrada en el art\u00edculo 150.19.d de la Constituci\u00f3n, en consonancia con el rol de interventor leg\u00edtimo y constitucional del Estado en la econom\u00eda, en los t\u00e9rminos del art. 334 constitucional. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ahora bien, en cuanto al cargo por la presunta violaci\u00f3n al principio de progresividad se\u00f1alan que la objeci\u00f3n principal del demandante consiste en lo siguiente:\u00a0 \u00a0 \u00a0<\/p>\n<p>\u201cel art\u00edculo 87 de la ley 1328 de 2009 consagra que los beneficiarios del programa BEPS, son \u00fanicamente aquellos que tienen la posibilidad de hacer aportes o ahorros peri\u00f3dicos o espor\u00e1dicos y cumplan la edad se\u00f1alada. Y que estas condiciones no son exigidas en la norma constitucional, raz\u00f3n por la cual, margina y excluye a las personas o grupos de personas que no pueden ahorrar o hacer aportes y que no han llegado a la edad fijada en el RPM priv\u00e1ndolos del derecho irrenunciable y del servicio p\u00fablico de car\u00e1cter obligatorio de la seguridad social no contributiva\u201d40. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Al respecto, indican que el actor desconoce que el modelo de protecci\u00f3n social nacional se basa en un esquema contributivo y que, teniendo en cuenta que la expansi\u00f3n de la cobertura de los sistemas de protecci\u00f3n social es una preocupaci\u00f3n global, la norma atacada es una expresi\u00f3n de esa ampliaci\u00f3n de la cobertura dirigida a una poblaci\u00f3n \u201ccon caracter\u00edsticas complejas, que ameritan programas diferenciados\u201d41. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En esta l\u00ednea, advierten que en el contexto internacional se ha impulsado una iniciativa basada en el concepto de \u201cPisos de Protecci\u00f3n Social\u201d. Afirman que esta iniciativa, fomentada por la OIT, \u201cse materializ\u00f3 con la Recomendaci\u00f3n No. 202 de 2012, y tiene dos objetivos b\u00e1sicos: a) establecer y mantener, seg\u00fan proceda, Pisos de Protecci\u00f3n Social como un elemento fundamental de sus sistemas nacionales de seguridad social; y b) poner en pr\u00e1ctica Pisos de Protecci\u00f3n Social en el marco de estrategias de extensi\u00f3n de la seguridad social que garanticen progresivamente niveles m\u00e1s elevados de seguridad social para el mayor n\u00famero de personas posible\u201d42. As\u00ed, resaltan que de lo anterior se desprende \u201cla necesaria obligaci\u00f3n de proveer seguridad social, en t\u00e9rminos universales, a trav\u00e9s de mecanismos que permitan una cobertura progresiva y sostenible, y no inmediata y absoluta\u201d43, y que este nivel de desarrollo \u201cdepende de las condiciones propias de cada pa\u00eds\u201d44. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ponen de presente que \u201cel sistema de protecci\u00f3n social en Colombia se fundamenta en la econom\u00eda formal, en consecuencia, las altas de tasas de informalidad no permiten la extensi\u00f3n de los beneficios de la protecci\u00f3n social a una parte importante de la poblaci\u00f3n, raz\u00f3n por la cual, se ha previsto una serie de programas y de iniciativas normativas que permitan mitigar los efectos de este riesgo de desprotecci\u00f3n\u201d45 y sostienen que el Estado ha desarrollado varias herramientas para lograr esa ampliaci\u00f3n progresiva de la cobertura. As\u00ed, se\u00f1alan que los BEPS son parte de esta estrategia de ampliaci\u00f3n a la que se refiere la Recomendaci\u00f3n 202 de la OIT y que \u201ceste mecanismo est\u00e1 previsto para aquellas personas que a\u00fan tengan posibilidad de ahorrar para proteger su vejez, pues para aquellas que no pueden hacerlo est\u00e1 previsto un mecanismo distinto por cuenta de la subcuenta de subsistencia del fondo de solidaridad pensional\u201d46. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En virtud de lo expuesto, los intervinientes ponen de presente que el mecanismo BEPS no incluye a los sectores que el actor echa de menos pues aquellos se refieren a un \u00e1mbito de protecci\u00f3n que los BEPS no pretenden cubrir, toda vez que \u201crepresenta s\u00f3lo una parte del dise\u00f1o institucional que pretende hacer frente a la informalidad laboral y la falta de cobertura del sistema de protecci\u00f3n social\u201d47. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Concepto de la Procuradora General de la Naci\u00f3n48 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Solicita declarar la exequibilidad de la disposici\u00f3n demandada. Frente al cargo por vulneraci\u00f3n del principio de unidad de materia, tras realizar una breve contextualizaci\u00f3n normativa de los BEPS, indica que \u201cla regulaci\u00f3n de un mecanismo de ahorro voluntario y flexible, como los BEPS, no resulta extra\u00f1a ni ajena a los prop\u00f3sitos de una reforma al sistema financiero, como la que implementa la Ley 1328 de 2009\u201d. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En primer lugar, precisa que la disposici\u00f3n guarda conexidad tem\u00e1tica con la Ley 1328 de 2009, en virtud de que este mecanismo se encuentra sujeto a la administraci\u00f3n por parte de una entidad autorizada y vigilada por la Superintendencia Financiera de Colombia, al suponer un modelo de captaci\u00f3n de recursos del p\u00fablico que se encuentra administrado por Colpensiones, en calidad de entidad financiera de car\u00e1cter especial. Asimismo, resalta que los BEPS operan por medio de un incentivo al ahorro, dentro del cual se incluye el acceso a micro-seguros, que son asuntos que le conciernen al sistema financiero. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En segundo lugar, encuentra acreditada la existencia de una \u201crelaci\u00f3n causal, teleol\u00f3gica y sistem\u00e1tica\u201d entre la disposici\u00f3n demandada y la ley de la que hace parte, por lo siguiente:\u00a0 \u00a0 \u00a0<\/p>\n<p>\u201c(i) las razones que llevaron a la expedici\u00f3n de la Ley 1328 de 2009 son las mismas que dieron lugar a la consagraci\u00f3n de la norma, esto es, la consecuci\u00f3n de un sistema financiero confiable y accesible al p\u00fablico; (ii) entre los objetivos perseguidos por la ley y su art\u00edculo 87 existe una identidad: la protecci\u00f3n del consumidor financiero; y (iii) la ley y su articulado constituyen un cuerpo ordenado que responde a una racionalidad interna guiada por la promoci\u00f3n del acceso a los servicios financieros y la consolidaci\u00f3n de la confianza en el sistema\u201d49. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Finalmente, en cuanto al cargo por la presunta vulneraci\u00f3n al principio de progresividad, sostiene que el art\u00edculo demandado no lo desconoce ya que busca desarrollarlo. \u00a0 \u00a0<\/p>\n<p>Al respecto, sostiene que \u201cla Constituci\u00f3n le confiri\u00f3 al legislador una amplia potestad de configuraci\u00f3n legislativa para determinar los requisitos de acceso a estos beneficios y su exigencia no constituye una vulneraci\u00f3n del principio de progresividad, sino que busca garantizar el ejercicio de los derechos sociales\u201d50. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. CONSIDERACIONES \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Competencia \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. La Corte Constitucional es competente para conocer de la demanda de la referencia, de conformidad con lo dispuesto en el art. 241.4 de la Constituci\u00f3n.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Aptitud de la demanda \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En atenci\u00f3n a la solicitud de Colpensiones, es preciso examinar si la demanda se ajusta a los m\u00ednimos argumentativos de los cuales depende la prosperidad del juicio abstracto de constitucionalidad. Solo en caso de evidenciar la aptitud de los cargos propuestos ser\u00e1 procedente la formulaci\u00f3n de un problema jur\u00eddico sustancial de constitucionalidad \u2013t\u00edtulo 3 infra\u2013 y proceder a su resoluci\u00f3n \u2013t\u00edtulos 4 a 5 infra\u2013. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En relaci\u00f3n con lo primero, esta Corte ha indicado que las demandas de inconstitucionalidad contra una ley se someten a exigencias de tipo formal y material, destinadas a la consolidaci\u00f3n de un verdadero problema de constitucionalidad que permita adelantar una discusi\u00f3n a partir de la confrontaci\u00f3n del contenido verificable de una disposici\u00f3n legal con el enunciado de un mandato superior. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En ese contexto, en reiterada jurisprudencia, ha se\u00f1alado que la competencia para ejercer el control de constitucionalidad de las leyes est\u00e1 atada al cumplimiento de dos presupuestos: que las normas sometidas a control se encuentren vigentes, produzcan efectos o tengan vocaci\u00f3n de producirlos, y que la demanda ciudadana re\u00fana los requisitos m\u00ednimos dispuestos en el art. 2 del Decreto Ley 2067 de 199151. De conformidad con esta disposici\u00f3n, las demandas de inconstitucionalidad deben se\u00f1alar: (i) las normas acusadas como inconstitucionales; (ii) las disposiciones constitucionales que se consideran infringidas; (iii) las razones por las cuales dichos textos han sido violados; (iv) en caso de que se cuestione el correcto tr\u00e1mite legislativo, se debe se\u00f1alar cu\u00e1l habr\u00eda debido observarse; y, en todos los casos, (v) la raz\u00f3n por la cual la Corte es competente. En especial, respecto de la tercera exigencia, esta Corte ha precisado que el demandante tiene el deber de formular correctamente el concepto de la violaci\u00f3n, raz\u00f3n por la cual, se le impone al ciudadano \u201cuna carga de contenido material y no simplemente formal\u201d, en el sentido de que no basta que el cargo formulado contra las normas legales se estructure a partir de cualquier tipo de razones o motivos, sino que se requiere que estas sean \u201cclaras, ciertas, espec\u00edficas, pertinentes y suficientes\u201d52. Esto es as\u00ed, ya que, \u00fanicamente a partir de su cumplimiento le es posible al juez constitucional realizar la confrontaci\u00f3n de las normas impugnadas con el texto superior. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Espec\u00edficamente, en cuanto a los requisitos de aptitud de un cargo por vulneraci\u00f3n al principio de unidad de materia, la jurisprudencia de esta Corte ha se\u00f1alado que \u201cel actor tiene la carga de demostrar (i) cu\u00e1l es el contenido material o tem\u00e1tico de la ley concernida; (ii) cu\u00e1les son las disposiciones de dicha ley que no guardan relaci\u00f3n de conexidad con dicha materia; (iii) las razones por las cuales considera que las normas se\u00f1aladas no guardan relaci\u00f3n con el tema de la ley y, por lo mismo, lesionan el art\u00edculo 158 de la Carta\u201d53. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Con el fin de evitar, en lo posible, un fallo inhibitorio, la apreciaci\u00f3n de estas exigencias debe hacerse en el auto admisorio; no obstante, la Corporaci\u00f3n ha determinado que en tal providencia se plasma un primer an\u00e1lisis que responde a una valoraci\u00f3n apenas sumaria de los cargos de la demanda, llevada a cabo por el magistrado sustanciador y que, en esa medida, no compromete ni define la competencia de la Sala Plena de la Corte, a la que corresponde la funci\u00f3n constitucional de decidir sobre las demandas de inconstitucionalidad que presenten los ciudadanos contra las leyes y los decretos con fuerza de ley (C.P. art. 241-4-5)54. En consecuencia, a la hora de realizar un an\u00e1lisis detallado de tales requerimientos -teniendo en cuenta las intervenciones ciudadanas y los dem\u00e1s elementos de juicio recaudados en el proceso- y encontrarlos incumplidos, la Corte deber\u00e1 declararse inhibida por ineptitud sustantiva de la demanda, de manera que se deje abierta la posibilidad de que se vuelva a cuestionar la correspondencia entre las normas acusadas y la Constituci\u00f3n.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. An\u00e1lisis de aptitud de los cargos de inconstitucionalidad \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. El cargo por la presunta vulneraci\u00f3n al principio de unidad de materia es apto \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El cargo por vulneraci\u00f3n al principio de unidad de materia acredita de manera adecuada los requisitos descritos. En efecto, el demandante expone de manera clara las razones por las cuales considera que el art. 87 de la Ley 1328 de 2009 no guarda conexidad tem\u00e1tica, causal, teleol\u00f3gica y sistem\u00e1tica con la ley en la cual se encuentra inserta, y, por tanto, desconoce el citado principio, en los t\u00e9rminos que lo regulan los arts. 158 y 169 de la Constituci\u00f3n.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Como se mencion\u00f3 previamente, el actor (i) resalta que el proyecto de ley presentado por el Gobierno nacional no inclu\u00eda inicialmente la disposici\u00f3n demandada; (ii) se\u00f1ala que el objetivo del proyecto de ley difiere de aquel buscado por la medida legislativa acusada y lo sustenta a partir de la trascripci\u00f3n de diversos apartes de la exposici\u00f3n de motivos y de la ponencia para primer debate en la cual se desarrolla el pliego de modificaciones a la iniciativa legislativa; (iii) advierte que la materia desarrollada por el art. 87 no se relaciona con el t\u00edtulo de la ley, pues no regula aspectos financieros, de seguros ni del mercado de valores, sino que \u201cregula un asunto relacionado con el derecho a la seguridad social\u201d55; (iv) indica que el tema central de la ley se encuentra determinado por su relaci\u00f3n con el sector financiero, asegurador o del mercado de valores y que el art\u00edculo acusado no trata sobre ellos; y (v) finalmente, sostiene que la norma acusada \u201ccarece de conexidad causal, teleol\u00f3gica, tem\u00e1tica o sistem\u00e1tica con la materia dominante de la ley 1328 y con su articulado\u201d56. \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En ese sentido, la Sala considera que el cargo es apto pues, (i) este es claro en la medida en que el actor expone una acusaci\u00f3n comprensible y motivada en la ausencia de conexidad entre el art. 87 y la ley que lo contiene; (ii) es espec\u00edfico y pertinente por cuanto el actor identifica con un grado razonable de precisi\u00f3n cu\u00e1l es el contenido material o tem\u00e1tico de la ley concernida, se\u00f1ala cu\u00e1les son las disposiciones de dicha ley que a su juicio no guardan relaci\u00f3n de conexidad con dicha materia, y precisa las razones por las cuales considera que las normas se\u00f1aladas no tienen relaci\u00f3n con el tema de la ley, a partir de conceptos de rango constitucional; (iii) es cierto en la medida en que la argumentaci\u00f3n recae sobre un contenido propio del art. 87 \u2013al regular una prestaci\u00f3n complementaria relacionada con la seguridad social\u2013 y no sobre una proposici\u00f3n jur\u00eddica inferida del actor; y (iv) es suficiente ya que los argumentos de la demanda cuentan con los elementos necesarios para generar una duda sobre la relaci\u00f3n y grado de conexidad entre su contenido normativo y aquel desarrollado en la ley de la cual hace parte. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Conviene aclarar que si bien el demandante menciona en su escrito los arts. 4 y 49 de la Constituci\u00f3n, al hacer referencia al presunto desconocimiento de la exigencia de unidad de materia, lo cierto es que no formul\u00f3 una argumentaci\u00f3n que permita comprender cu\u00e1l es el motivo por el cual considera que estos fueron vulnerados por la disposici\u00f3n acusada ni cu\u00e1l es su relaci\u00f3n con el citado principio. Por tanto, el pronunciamiento de la Sala Plena se limitar\u00e1 a estudiar el cargo por el presunto desconocimiento de los arts. 158 y 169 de la Constituci\u00f3n, al haber sido formulado de manera adecuada. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. El cargo por la presunta vulneraci\u00f3n del principio de progresividad no es apto \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De conformidad con el cargo inicialmente admitido57, para el demandante, el precepto acusado desconoce el referido principio en su faceta de prohibici\u00f3n de regresividad, \u00a0 \u00a0<\/p>\n<p>\u201cporque en lugar de avanzar ampliando progresivamente la cobertura de la seguridad social como lo ordenan las disposiciones citadas, despoja y excluye a grupos vulnerables de personas del derecho a la seguridad social al exigirles para acceder a los BEPS requisitos que no aparecen en el AL 01 de 2005 ni en el t\u00edtulo IV de la ley 100, art\u00edculos 257, 258, 259 y 260 que establecen la \u2018prestaci\u00f3n especial para la vejez\u2019, constituy\u00e9ndose en una disposici\u00f3n regresiva y que prima facie es inconstitucional\u201d58.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. As\u00ed, advierte que la norma es \u201cregresiva e injusta\u201d59 pues retrocede \u201cfrente al nivel de protecci\u00f3n al que han llegado miles de personas vulnerables por su condici\u00f3n econ\u00f3mica porque les cierra las puertas para acceder a los BEPS si no hacen ahorros o aportes peri\u00f3dicos o espor\u00e1dicos\u201d60.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. A juicio de la Sala, este cargo por presunta vulneraci\u00f3n del principio de progresividad no es apto, en cuanto las razones propuestas para su fundamentaci\u00f3n no son ciertas, espec\u00edficas ni suficientes. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El accionante sostiene que la disposici\u00f3n demandada desconoce el principio de no regresividad en materia de seguridad social; sin embargo, no cumple con la carga de demostrar que dicho desconocimiento se desprenda de manera razonable de su texto, por cuanto omite explicar cu\u00e1l era el \u00e1mbito de protecci\u00f3n del cual gozaban los sujetos que menciona, antes de la expedici\u00f3n de la norma acusada, punto de partida para valorar el presunto trato regresivo de la disposici\u00f3n posterior. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. As\u00ed las cosas, la l\u00ednea argumentativa propuesta por el demandante, (i) desconoce el requisito de certeza, por cuanto incumple la carga de demostrar que la presunta regresividad se deriva de manera razonable del contenido de la disposici\u00f3n acusada; (ii) sus argumentos son vagos y abstractos, toda vez que en la elaboraci\u00f3n del cargo se refiere a la exclusi\u00f3n de un grupo de sujetos que no determina de manera clara ni demuestra que est\u00e9n cubiertos por el \u00e1mbito de protecci\u00f3n normativo respecto del cual se considera que la norma acusada ha retrocedido; y (iii) la ausencia de \u201cla exposici\u00f3n de todos los elementos de juicio (argumentativos y probatorios) necesarios para iniciar el estudio de constitucionalidad respecto del precepto objeto de reproche\u201d63 impide que los argumentos con los cuales pretende conformar el cargo den cabida a una duda m\u00ednima sobre la inconstitucionalidad del art\u00edculo demandado. Veamos: \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Tal y como lo ha precisado esta Corporaci\u00f3n en otras oportunidades, \u00a0 \u00a0<\/p>\n<p>\u201cConsiderando la estructura del mandato de progresividad en su variante de prohibici\u00f3n de retroceso injustificado, la activaci\u00f3n de la competencia de la Corte para emprender el juicio exige que al formular la acusaci\u00f3n los ciudadanos aporten argumentos que de manera espec\u00edfica se orienten a indicar, por un lado, que la medida constituye en efecto un retroceso en el grado de protecci\u00f3n del derecho de que se trate y, de otro, que dicho retroceso no encuentra una justificaci\u00f3n suficiente. La primera de tales exigencias impone que la acusaci\u00f3n evidencie que la modificaci\u00f3n normativa -analizada en el contexto del r\u00e9gimen al que se integra y luego de una comparaci\u00f3n con el r\u00e9gimen preexistente- constituye un deterioro relevante en el grado de protecci\u00f3n del derecho identificado. No basta, a juicio de la Corte, que se enuncien las diferencias entre disposiciones aisladas cuyo significado jur\u00eddico depende de su relaci\u00f3n con las otras normas del cuerpo normativo del que hacen parte\u201d64. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En este sentido, el actor omite hacer referencia al r\u00e9gimen preexistente bajo el cual el grupo poblacional que cita en su demanda encontraba un grado de protecci\u00f3n mayor al que la norma demandada le confiere. Esto es de suma importancia en la formulaci\u00f3n de un cargo de esta estirpe, por cuanto de la determinaci\u00f3n precisa del r\u00e9gimen preexistente es que es posible determinar con certeza que el efecto regresivo que se atribuye a la disposici\u00f3n acusada efectivamente se presenta. De lo contrario, el demandante le estar\u00eda asignando a la Corte el deber de analizar el universo normativo de la seguridad social, relacionado con la norma acusada, para establecer cu\u00e1l era el supuesto de protecci\u00f3n anterior y contrastarlo con el actual \u2013el que regula la disposici\u00f3n demandada\u2013 para determinar si la acusaci\u00f3n del actor es cierta o no. Esta deficiencia argumentativa desconoce las exigencias de certeza y especificidad, en relaci\u00f3n con la presunta vulneraci\u00f3n del principio de progresividad en la faceta prestacional del derecho a la seguridad social, toda vez que le asigna a la Sala la funci\u00f3n de completar la estructuraci\u00f3n del cargo, con el fin de determinar si el contenido normativo de car\u00e1cter regresivo del que se acusa a la disposici\u00f3n efectivamente existe. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El requisito de certeza en la formulaci\u00f3n del cargo le asigna al demandante \u201cla carga de demostrar que es razonable -a partir de est\u00e1ndares b\u00e1sicos de interpretaci\u00f3n- derivar de una disposici\u00f3n vigente, el significado normativo -norma- cuya constitucionalidad se cuestiona, de modo que \u2018la interpretaci\u00f3n que se acusa debe ser plausible y adem\u00e1s debe desprenderse del enunciado normativo acusado\u2019\u201d65. En consecuencia, si el actor acusa al art. 87 de la Ley 1328 de 2009 de contar con un contenido normativo que es regresivo de cara al \u00e1mbito de protecci\u00f3n prestacional del derecho a la seguridad social, en la medida en que contiene unos limitantes que excluyen a ciertas personas de dicho espectro de protecci\u00f3n, es indispensable que el demandante demuestre de manera previa que dichas personas efectivamente eran destinatarias del programa BEPS \u2013o del instrumento normativo que regulaba una an\u00e1loga materia\u2013 y que la norma retrocedi\u00f3 en su protecci\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Al referirse a la estructura del juicio de constitucionalidad de una norma acusada por la vulneraci\u00f3n del principio de no regresividad, la jurisprudencia constitucional ha se\u00f1alado que este se adelanta por medio de un test de no regresividad que contiene, a saber, tres elementos. El primero, \u201ctiene a su vez una condici\u00f3n habilitante para efectos de desplegar el control de constitucionalidad. El debate constitucional no se puede adelantar si la medida objeto de control no es regresiva\u201d66. En relaci\u00f3n con este, ha se\u00f1alado: \u00a0 \u00a0<\/p>\n<p>\u201cPara precisar si la disposici\u00f3n demandada constituye una medida regresiva es indispensable adelantar un cotejo entre la norma de la disposici\u00f3n demandada y la norma que se afectar\u00eda con dicho cambio normativo. \u00a0Debe verificarse entonces que ambas normas guarden una suerte de identidad entre s\u00ed, o, en otras palabras, que ambas regulen un mismo supuesto de hecho y una misma consecuencia jur\u00eddica. Esta verificaci\u00f3n se puede adelantar a partir de una comparaci\u00f3n entre los elementos normativos de la disposici\u00f3n posterior (demandada) con los elementos normativos de la disposici\u00f3n anterior (conducta regulada, circunstancias normativas, destinatarios, beneficiarios, titulares, sujetos obligados, y dem\u00e1s elementos que puedan ser relevantes seg\u00fan el caso). Para la Corte, el escrutinio constitucional comprende \u2018una comparaci\u00f3n con los est\u00e1ndares de protecci\u00f3n anteriores, es decir, el juicio de constitucionalidad de estas medidas incluye tambi\u00e9n un examen de evoluci\u00f3n cronol\u00f3gica de las garant\u00edas asociadas al derecho correspondiente\u2019\u201d67. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De esta manera, el punto de partida para el estudio de constitucionalidad en este tipo de asuntos exige el que demandante precise el est\u00e1ndar de comparaci\u00f3n entre el \u00e1mbito de protecci\u00f3n anterior y el actual, al que est\u00e1 sujeto un mismo grupo de sujetos. De lo contrario, el juicio que tendr\u00eda que adelantar la Corte estar\u00eda sujeto a la eventual determinaci\u00f3n que ella haga de uno de los componentes de la comparaci\u00f3n, lo que ir\u00eda en desmedro del control de constitucionalidad que debe adelantar la Corte \u201cen los estrictos y precisos t\u00e9rminos\u201d del art. 241 de la Carta, pues estar\u00eda participando en la elaboraci\u00f3n del cargo en desarrollo de un control oficioso, cuando es claro que,\u00a0 \u00a0 \u00a0<\/p>\n<p>\u201cno corresponde a la Corte Constitucional revisar oficiosamente las leyes sino examinar aquellas que han sido demandadas por los ciudadanos, lo cual implica que el tr\u00e1mite de la acci\u00f3n p\u00fablica s\u00f3lo puede adelantarse cuando efectivamente haya habido demanda, esto es, una acusaci\u00f3n en debida forma de un ciudadano contra una norma legal\u201d68. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. As\u00ed, entonces, en el presente asunto, el actor no cumple con esta carga, pues omite por completo la explicaci\u00f3n de cu\u00e1l era el \u00e1mbito de protecci\u00f3n al que estaban sujetas las personas vulnerables bajo el programa BEPS antes de la expedici\u00f3n de la disposici\u00f3n acusada.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El actor solo afirma, de manera imprecisa y abstracta, que el Acto Legislativo 01 de 2005 no se\u00f1ala los requisitos que el art. 87 de la Ley 1328 de 2009 exige para acceder al programa que, dicho sea de paso, nace precisamente en virtud del desarrollo legislativo que hace la disposici\u00f3n acusada; y, en vez de referirse al programa BEPS, alude al programa de la prestaci\u00f3n especial de vejez regulada en el art. 257 de la Ley 100 de 1993, sin explicar porque los destinatarios de esta prestaci\u00f3n son excluidos por el art\u00edculo demandado.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Esta carencia impide que la Corte pueda ejercer su competencia de control constitucional, pues para ello tendr\u00eda que llenar oficiosamente el vac\u00edo argumentativo del demandante, con el fin de determinar cu\u00e1l es el criterio de comparaci\u00f3n que contiene el \u00e1mbito de protecci\u00f3n anterior y que ha sido presuntamente derruido por la disposici\u00f3n demandada. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por estas razones, para la Sala, el pretendido cargo de inconstitucionalidad por la presunta vulneraci\u00f3n del principio de progresividad no es apto y, por tanto, se inhibir\u00e1 de emitir un pronunciamiento de fondo. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Problema jur\u00eddico y metodolog\u00eda de resoluci\u00f3n \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En consecuencia, a la aptitud del cargo de que trata el t\u00edtulo 2.1.1 supra, le corresponde a la Sala decidir si el art. 87 de la Ley 1328 de 2009 desconoce el principio de unidad de materia, consagrado en los arts. 158 y 169 de la Constituci\u00f3n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para tales efectos, la Sala reiterar\u00e1 su jurisprudencia acerca del contenido del citado principio y el est\u00e1ndar de control aplicable \u2013t\u00edtulo 4 infra\u2013, a partir del cual valorar\u00e1 la compatibilidad de la disposici\u00f3n demandada con la citada garant\u00eda constitucional \u2013t\u00edtulo 5 infra\u2013. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El principio de unidad de materia legislativa \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el presente apartado se hace referencia al alcance y fundamentos del principio de unidad de materia \u2013t\u00edtulo 4.1 infra\u2013 y al est\u00e1ndar de control que ha se\u00f1alado en forma reiterada la jurisprudencia constitucional para valorar medidas legislativas presuntamente incompatibles con este \u2013t\u00edtulo 4.2 infra\u2013. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Alcance y fundamentos del principio de unidad de materia \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El principio de unidad de materia hace referencia a la coherencia interna exigida en el contenido de las leyes69, con sustento constitucional en los arts. 158 y 169 Superiores. Seg\u00fan el primero de estos, \u201ctodo proyecto de ley debe referirse a una misma materia y ser\u00e1n inadmisibles las disposiciones o modificaciones que no se relacionen con ella\u201d70. Mediante el segundo se establece que \u201cel t\u00edtulo de las leyes debe corresponder precisamente a su contenido\u201d.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El objetivo de esta garant\u00eda es racionalizar y tecnificar la actividad legislativa71, de tal manera que (i) exista coherencia sist\u00e9mica72 al interior de una ley en particular y en relaci\u00f3n con el resto del ordenamiento jur\u00eddico; (ii) se evite el tr\u00e1mite y aprobaci\u00f3n de normas extra\u00f1as, aisladas, inconexas y contrarias al objeto de una ley en particular, respecto de las cuales no ha existido un verdadero debate legislativo73; y (iii) se consolide la voluntad democr\u00e1tica en el marco de una deliberaci\u00f3n p\u00fablica transparente. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por consiguiente, de este principio se deriva el deber de que el procedimiento legislativo responda a un contexto tem\u00e1tico preciso, que propenda por un di\u00e1logo legislativo coherente, informado y productivo74 y que, en consecuencia, (i) garantice la protecci\u00f3n de la seguridad jur\u00eddica75 y (ii) se facilite el conocimiento y cumplimiento de la norma por parte de la sociedad y, en particular, de sus destinatarios concretos76. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De esta manera, los arts. 158 y 169 de la Constituci\u00f3n incorporan un instrumento de transparencia, racionalidad y tecnificaci\u00f3n de la actividad legislativa que se materializa en la coherencia interna de las leyes, de manera tal que sus disposiciones est\u00e9n directamente relacionadas con un mismo n\u00facleo tem\u00e1tico y sean fruto de la deliberaci\u00f3n p\u00fablica. Este instrumento garantiza una deliberaci\u00f3n democr\u00e1tica, informada y transparente77, que pretendidamente busca repercutir en cuerpos normativos coherentes y arm\u00f3nicos, que garanticen su eficacia. El \u00e1mbito de transparencia de esta exigencia constitucional tiende a evitar que durante cualquier etapa del procedimiento legislativo se les d\u00e9 tr\u00e1mite a disposiciones respecto de las cuales no se observa una conexi\u00f3n unitaria entre los temas que se someten al proceso legislativo78 y se profieran normas sobre las cuales no se ha surtido el debate democr\u00e1tico del cual debe nacer toda disposici\u00f3n como manifestaci\u00f3n de la voluntad plural. Por su parte, la perspectiva de la racionalizaci\u00f3n de los procesos legislativos de cara a la exigencia de coherencia material tiene como finalidad que los debates que se surtan en el Congreso de la Rep\u00fablica, como foro natural de representaci\u00f3n democr\u00e1tica, se concentren en materias que hayan sido objeto de un proceso deliberativo propio de la reflexi\u00f3n y an\u00e1lisis democr\u00e1tico. Sin duda, la dispersi\u00f3n, la incongruencia y la incoherencia tem\u00e1tica constituyen un obst\u00e1culo a este objetivo, motivo por el cual el constituyente dispuso que los contenidos de un mismo cuerpo normativo deban enmarcarse en una misma materia.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para hacer compatibles estas exigencias adscritas al principio de unidad de materia con el principio democr\u00e1tico79, la valoraci\u00f3n acerca de su satisfacci\u00f3n en un caso concreto debe fundamentarse en criterios de razonabilidad y objetividad, a partir de la valoraci\u00f3n de elementos de conexidad (i) causal, (ii) tem\u00e1tica, (iii) teleol\u00f3gica y (iv) sistem\u00e1tica. Estos conceptos han sido definidos por la jurisprudencia constitucional en los siguientes t\u00e9rminos80:\u00a0 \u00a0 \u00a0<\/p>\n<p>Conexidad causal: [\u2026] identidad que debe haber entre la ley y cada una de sus disposiciones, vista a partir de los motivos que dieron lugar a su expedici\u00f3n, valga decir, hace relaci\u00f3n a que las razones de la expedici\u00f3n de la ley sean las mismas que dan lugar a la consagraci\u00f3n de cada uno de sus art\u00edculos en particular, dentro del contexto de la posible complejidad tem\u00e1tica de la ley. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Conexidad teleol\u00f3gica: [\u2026] identidad en los fines u objetivos que persigue la ley, tanto en su conjunto general como en cada una de sus disposiciones en particular, es decir, la ley como unidad y cada una de sus disposiciones en particular deben dirigirse a alcanzar un mismo designio o designios, nuevamente dentro del contexto de la posible complejidad tem\u00e1tica de la ley. \u00a0<\/p>\n<p>Conexidad sist\u00e9mica: [\u2026] relaci\u00f3n que debe haber entre todas y cada una de las disposiciones de una ley, de tal suerte que ellas puedan constituir un cuerpo organizado que responde a una racionalidad interna\u201d81. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por su parte, la conexidad entre el t\u00edtulo de la ley y el de las disposiciones contenidas en esta se constituye en una garant\u00eda del principio de seguridad jur\u00eddica. En este caso, el estudio constitucional exige verificar los siguientes aspectos: \u00a0 \u00a0<\/p>\n<p>\u201ci) que el t\u00edtulo de la ley no contenga elementos discriminatorios; ii) que el t\u00edtulo de la ley no sustituya la descripci\u00f3n general del contenido de la misma; iii) que entre el t\u00edtulo y el contenido de la ley debe existir, necesariamente, una relaci\u00f3n de conexidad; y iv) que el t\u00edtulo no debe conceder reconocimientos, privilegios u honores a una persona espec\u00edfica\u201d82. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Est\u00e1ndar o metodolog\u00eda para valorar un presunto desconocimiento de las exigencias del principio de unidad de materia en el tr\u00e1mite legislativo \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para determinar si en el tr\u00e1mite legislativo se desconocieron las exigencias del principio de unidad de materia en relaci\u00f3n con un cargo apto de inconstitucionalidad, la jurisprudencia constitucional ha precisado que se debe determinar el contenido tem\u00e1tico de la ley \u2013su materia\u2013 y, a partir este, valorar si entre la disposici\u00f3n demandada y esta materia existe una relaci\u00f3n de conexidad constitucionalmente aceptable83. Para determinar lo primero, ha indicado que son elementos relevantes el t\u00edtulo o ep\u00edgrafe de la ley; el contexto o contenido b\u00e1sico de la disposici\u00f3n demandada y los antecedentes legislativos de esta y de la ley, valga decir, su exposici\u00f3n de motivos, informes de ponencia, actas de los debates en comisiones y en plenarias y los textos originales, modificados y definitivos de la norma acusada84. Para valorar lo segundo, la jurisprudencia ha precisado que, salvo que se trate de una ley aprobatoria del plan nacional de desarrollo, en el que el est\u00e1ndar de unidad de materia es estricto85, la conexidad puede ser causal, tem\u00e1tica, teleol\u00f3gica o sistem\u00e1tica, en los t\u00e9rminos referidos en el t\u00edtulo anterior. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En relaci\u00f3n con esta \u00faltima exigencia, se debe tener en cuenta que el principio de unidad de materia en relaci\u00f3n con el principio democr\u00e1tico tiene una doble connotaci\u00f3n: como garant\u00eda y l\u00edmite86, dado que cuando se trata de asuntos inconexos, sin un n\u00facleo tem\u00e1tico identificable, la voluntad legislativa no se configura de manera adecuada87, de all\u00ed que se justifique la inexequibilidad de la disposici\u00f3n que particularmente se valora. Sin embargo, el principio en estudio no puede sobrepasar su finalidad al punto de anular la voluntad democr\u00e1tica88, valor fundante del Estado de Derecho y, por ende, con un mayor peso abstracto89. Por consiguiente, por regla general, el estudio acerca de la exigencia de unidad de materia en la ley es flexible y la intensidad con la cual se realiza el control es menor90: \u00a0 \u00a0<\/p>\n<p>\u201cCuando los tribunales constitucionales entran a determinar si una ley ha cumplido o no con el principio de unidad de materia deben ponderar tambi\u00e9n el principio democr\u00e1tico que alienta la actividad parlamentaria y en esa ponderaci\u00f3n pueden optar por ejercer un control de diversa intensidad. Esto es, el alcance que se le reconozca al principio de unidad de materia tiene implicaciones en la intensidad del control constitucional pues la percepci\u00f3n que se tenga de \u00e9l permite inferir de qu\u00e9 grado es el rigor de la Corte al momento del examen de las normas. As\u00ed, si se opta por un control r\u00edgido, violar\u00eda la Carta toda norma que no est\u00e9 directamente relacionada con la materia que es objeto de regulaci\u00f3n y, por el contrario, si se opta por un control de menor rigurosidad, s\u00f3lo violar\u00edan la Carta aquellas disposi\u00adciones que resulten ajenas a la materia regulada. La Corte estima que un control r\u00edgido desconocer\u00eda la vocaci\u00f3n democr\u00e1tica del Congreso y ser\u00eda contrario a la cl\u00e1usula general de competencia que le asiste en materia legislativa. Ante ello, debe optarse por un control que no opte por un rigor extremo\u201d 91. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En esa medida, la inexequibilidad de apartes, segmentos o proposiciones de una ley, solo tendr\u00e1 cabida cuando la ausencia de conexidad entre la materia dominante de la disposici\u00f3n acusada y la ley en la cual se inserta, se establezca bajo criterios razonables y objetivos. As\u00ed, entonces, seg\u00fan la jurisprudencia constitucional, el concepto de materia debe entenderse desde una perspectiva \u201camplia y global\u201d92, de tal suerte que \u201cpermita comprender diversos temas cuyo l\u00edmite es la coherencia que la l\u00f3gica y la t\u00e9cnica jur\u00eddica suponen para valorar el proceso de formaci\u00f3n de la ley\u201d93. Por ende, una misma ley puede tener varios contenidos tem\u00e1ticos \u201csiempre y cuando los mismos se relacionen entre s\u00ed y \u00e9stos a su vez con la materia de la ley\u201d94. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Soluci\u00f3n del problema jur\u00eddico \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para la Sala, el art. 87 de la Ley 1328 de 2009 respeta las exigencias adscritas al principio de unidad de materia dispuesto en los art. 158 y 169 de la Constituci\u00f3n, en la medida en que su contenido normativo guarda una relaci\u00f3n objetiva y razonable con la materia general y la tem\u00e1tica particular desarrollada en la Ley 1328 de 2009. \u00a0A tal conclusi\u00f3n llega la Sala luego de aplicar la metodolog\u00eda descrita, en virtud de la cual (i) har\u00e1 referencia al contenido tem\u00e1tico de la Ley 1328 de 2009 \u2013t\u00edtulo 5.1. infra\u2013 y (ii) contrastar\u00e1 este con el contenido normativo de la disposici\u00f3n acusada para evidenciar su conexidad \u2013t\u00edtulo 5.2. infra\u2013. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Contenido tem\u00e1tico de la Ley 1328 de 2009 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para determinar el contenido tem\u00e1tico de la Ley 1328 de 2009, la Sala (i) detallar\u00e1 los antecedentes del tr\u00e1mite legislativo \u2013t\u00edtulo 5.1.1. infra\u2013 y (ii) har\u00e1 referencia a la relaci\u00f3n entre su n\u00facleo tem\u00e1tico y el t\u00edtulo que la identifica. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. Los antecedentes legislativos de la Ley 1328 de 2009 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Seg\u00fan consta en la Gaceta del Congreso No. 138 del 11 de abril de 2008 en la que se public\u00f3 el Proyecto de ley 282 de 2008 C\u00e1mara \u201cpor la cual se dictan normas en materia financiera, de seguros, del mercado de valores y otras disposiciones\u201d, el ministro de Hacienda y Cr\u00e9dito P\u00fablico present\u00f3 una iniciativa que constaba de 60 art\u00edculos, divididos en 8 t\u00edtulos, a saber: \u201cT\u00edtulo I. Del R\u00e9gimen de protecci\u00f3n al Consumidor Financiero\u201d; \u201cT\u00edtulo II. De las Facultades de Intervenci\u00f3n del Gobierno Nacional\u201d; \u201cT\u00edtulo III. De la estructura del Sistema Financiero\u201d; \u201cT\u00edtulo IV. Del Fondo de Garant\u00edas de Instituciones Financieras\u201d; \u201cT\u00edtulo V. Del R\u00e9gimen Financiero de los Fondos de Pensi\u00f3n Obligatoria y Cesant\u00eda\u201d; \u201cT\u00edtulo VI. De la Liberalizaci\u00f3n Comercial en materia de Servicios Financieros\u201d; \u201cT\u00edtulo VII. De la Superintendencia Financiera de Colombia\u201d; y, finalmente, \u201cT\u00edtulo VIII. Disposiciones Finales\u201d.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el ac\u00e1pite de \u201cIntroducci\u00f3n\u201d de la exposici\u00f3n de motivos, el Gobierno nacional indic\u00f3 que la finalidad del proyecto era lograr una mayor \u201cprofundizaci\u00f3n\u201d95 del sistema financiero colombiano y mejorar el desarrollo del mercado de capitales. Esto se traducir\u00eda, \u201cen una adecuada canalizaci\u00f3n de ahorros hacia inversiones productivas, un eficiente sistema de pagos que facilita las transacciones entre agentes econ\u00f3micos y un apropiado monitoreo de los riesgos empresariales\u201d96. Para lograr esto resultaba necesario promover el acceso \u201cpor parte de la poblaci\u00f3n m\u00e1s pobre de Colombia y los sectores productivos m\u00e1s marginados del sector financiero formal (micro y peque\u00f1as empresas)\u201d97 al cr\u00e9dito y a mayores servicios financieros. De esta forma, ante la ampliaci\u00f3n del sistema financiero y una mayor bancarizaci\u00f3n de la poblaci\u00f3n era indispensable avanzar en el fortalecimiento de los mecanismos de protecci\u00f3n del consumidor financiero.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Habiendo precisado el objeto de la reforma, la exposici\u00f3n de motivos se propuso explicar cada uno de los t\u00edtulos del proyecto anteriormente mencionados. As\u00ed, por su especial relevancia para el presente asunto se har\u00e1 referencia, en particular, a las razones que fundamentaron la adopci\u00f3n de los t\u00edtulos II y V, relacionados con las facultades de intervenci\u00f3n del gobierno nacional y el r\u00e9gimen financiero de los fondos de pensi\u00f3n obligatoria y cesant\u00edas. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En relaci\u00f3n con el alcance de las disposiciones que integraban el t\u00edtulo II de la iniciativa, la exposici\u00f3n de motivos precis\u00f3 que uno de los objetivos de este era incorporar instrumentos de intervenci\u00f3n relacionados con los recursos y la administraci\u00f3n de los fondos de pensiones obligatorias. As\u00ed, en cuanto a este elemento, la exposici\u00f3n de motivos se\u00f1al\u00f3:\u00a0 \u00a0 \u00a0<\/p>\n<p>\u201cuno de los prop\u00f3sitos principales del proyecto de ley es adoptar un esquema de \u2018multifondos\u2019 para el r\u00e9gimen de ahorro individual con solidaridad en pensiones obligatorias\u201d98 || \u201cPara el efecto, se se\u00f1ala como objetivo de intervenci\u00f3n que los recursos de pensi\u00f3n obligatoria est\u00e9n invertidos en fondos que consideren las edades, expectativas y perfiles de riesgo de afiliados, con el objetivo de maximizar la rentabilidad ajustada por riesgo para brindar las prestaciones previstas en la Ley en favor de estos. [\u2026] Igualmente se plantea como objetivo de intervenci\u00f3n el promover en los afiliados al r\u00e9gimen de ahorro individual con solidaridad el conocimiento claro de sus derechos y deberes, as\u00ed como de las caracter\u00edsticas del mismo, de tal manera que les permita adoptar decisiones informadas, en especial de los efectos que de acuerdo con la ley se derivan de la vinculaci\u00f3n a dicho r\u00e9gimen\u201d99. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En esta l\u00ednea, frente a las modificaciones del r\u00e9gimen financiero de los fondos de pensi\u00f3n obligatoria (t\u00edtulo V de la iniciativa), en la exposici\u00f3n de motivos el Gobierno nacional se\u00f1al\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cLos denominados \u2018Multifondos\u2019 permiten una adaptaci\u00f3n m\u00e1s flexible a los distintos perfiles de riesgo de los afiliados y, al mismo tiempo, posibilitan una gesti\u00f3n m\u00e1s eficiente con el \u2018ciclo de vida\u2019, recuperando la consistencia regulatoria entre instrumentos y objetivos. \u00a0<\/p>\n<p>As\u00ed, incrementan la eficiencia del sistema pensional para cumplir con su objetivo, permiten segmentar a los afiliados en distintos perfiles de riesgo-retorno y aumentan la rentabilidad para afiliados menos aversos al riesgo, a su vez que protegen el valor del beneficio para afiliados pr\u00f3ximos a pensionarse\u201d100. \u00a0<\/p>\n<p>1. De lo anterior se desprende que el mecanismo de multifondos que pretend\u00eda implementar el proyecto ten\u00eda el objeto de mejorar las condiciones de funcionamiento del r\u00e9gimen de ahorro individual maximizando la rentabilidad de los recursos invertidos que garantizan el acceso a la prestaci\u00f3n pensional, buscando una mayor eficiencia del sistema pensional en el cumplimiento de su objetivo. Esto evidencia la estrecha relaci\u00f3n entre las modificaciones de car\u00e1cter financiero a la normativa pensional y sus objetivos sociales tendientes a la garant\u00eda de los derechos fundamentales de los afiliados, desde su g\u00e9nesis en la formulaci\u00f3n del proyecto. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ahora, analizando una etapa posterior del tr\u00e1mite legislativo, seg\u00fan consta en la Gaceta del Congreso No. 341 del 10 de junio de 2008, la ponencia para primer debate al Proyecto de ley 282 de 2008 C\u00e1mara, 286 de 2008 Senado \u201cpor la cual se dictan normas en materia, financiera, de seguros, del mercado de valores y otras disposiciones\u201d fue presentada a consideraci\u00f3n de las comisiones terceras conjuntas de Senado y C\u00e1mara. Para efectos del an\u00e1lisis que corresponde hacer en el presente proceso, resulta pertinente trascribir los siguientes apartes de esta, que resultan relevantes, pues contienen los elementos que constitu\u00edan, a juicio de los ponentes, los \u201cprincipales aspectos del proyecto\u201d101:\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En primer lugar, en relaci\u00f3n con el t\u00edtulo II, relacionado con las \u201cfacultades de intervenci\u00f3n del Gobierno nacional\u201d, la ponencia sostuvo que el proyecto de reforma financiera buscaba principalmente \u201clograr una transformaci\u00f3n de fondo en la forma como se administran los recursos provenientes de los aportes de pensi\u00f3n obligatoria en el R\u00e9gimen de Ahorro Individual con Solidaridad (RAIS), buscando fundamentalmente optimizar los rendimientos de dichos aportes, con una exposici\u00f3n al riesgo limitada, para acrecentar el capital de los colombianos a la hora de pensionarse y con ello lograr el fin \u00faltimo del sistema de que m\u00e1s colombianos puedan gozar de su pensi\u00f3n en el futuro\u201d 102. Para ello, adujo la ponencia que se deb\u00eda facultar al Gobierno nacional para que reglamentara la organizaci\u00f3n del Fondo de Garant\u00eda de Pensi\u00f3n M\u00ednima y as\u00ed optimizar su funcionamiento dentro del andamiaje del sistema pensional \u201cpara dar el mayor cubrimiento posible de beneficios pensionales a m\u00e1s colombianos\u201d103. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En segundo lugar, en relaci\u00f3n con el t\u00edtulo VI (en la versi\u00f3n de la iniciativa, t\u00edtulo V), relacionado con el \u201cr\u00e9gimen financiero de los fondos de pensi\u00f3n obligatoria y cesant\u00eda\u201d, la ponencia puso de presente que el esquema de multifondos incrementar\u00eda \u201cla eficiencia del sistema pensional mediante la segmentaci\u00f3n de los afiliados en distintos perfiles de riesgo-retorno y aumentando la rentabilidad para afiliados menos aversos al riesgo, permiti\u00e9ndoles acumular un mayor capital para su pensi\u00f3n, a la vez que protege el valor del capital ya acumulado para afiliados pr\u00f3ximos a pensionarse, consecuentemente m\u00e1s aversos al riesgo\u201d104. Esto refleja, una vez m\u00e1s, la estrecha relaci\u00f3n entre el car\u00e1cter financiero del proyecto y la materializaci\u00f3n de los objetivos del sistema pensional.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por otro lado, en dicha gaceta los ponentes presentaron el pliego de modificaciones de fondo al articulado. Es en este punto del tr\u00e1mite legislativo en el que aparece por primera vez la propuesta de adicionar al articulado el concepto de \u201cbeneficios econ\u00f3micos peri\u00f3dicos\u201d, BEPS. Al respecto, los ponentes expresaron lo siguiente: \u00a0 \u00a0<\/p>\n<p>\u201cII. Modificaciones de fondo al articulado \u00a0<\/p>\n<p>En relaci\u00f3n con el articulado presentado, se realizaron modificaciones de forma y de fondo. A continuaci\u00f3n, se rese\u00f1ar\u00e1n junto son su justificaci\u00f3n las modificaciones de fondo. [\u2026] \u00a0<\/p>\n<p>9. T\u00edtulo VIII (ahora IX) Otras disposiciones [\u2026] \u00a0<\/p>\n<p>9.9 Beneficios Econ\u00f3micos Peri\u00f3dicos BEP \u00a0<\/p>\n<p>Existe un alto porcentaje de poblaci\u00f3n, no vinculada formalmente al mercado laboral, que a lo largo de la vida no logra generar niveles de ahorro suficientes para acumular el capital requerido para una pensi\u00f3n m\u00ednima, poblaci\u00f3n que es necesario incorporar a los mecanismos estatales de protecci\u00f3n social. \u00a0<\/p>\n<p>El Acto Legislativo 01 de 2005, en su inciso 6\u00b0 abre la posibilidad de enfrentar esta situaci\u00f3n, con respecto a lo cual dispone: \u2018la ley podr\u00e1 determinar los casos en que se puedan conceder beneficios econ\u00f3micos peri\u00f3dicos inferiores al salario m\u00ednimo, a personas de escasos recursos que no cumplan con las condiciones requeridas para tener derecho a una pensi\u00f3n\u2019. \u00a0<\/p>\n<p>Los estudios realizados muestran que estos grupos de poblaci\u00f3n tienen cierta capacidad de ahorro, la cual se busca estimular con esta propuesta para lograr un resultado que a largo plazo permita una alternativa formal de Beneficios Econ\u00f3micos Peri\u00f3dicos, BEP. \u00a0<\/p>\n<p>El instrumento para este tipo de poblaci\u00f3n debe basarse en un esfuerzo personal, ser flexible y con la institucionalidad adecuada y adem\u00e1s debe permitir reunir los recursos ahorrados, incluyendo las devoluciones de aportes del R\u00e9gimen Contributivo de Pensiones (cuando no se cumplan los requisitos para una pensi\u00f3n), con el fin de acceder a esquemas alternativos de beneficios al final de la vida laboral. \u00a0<\/p>\n<p>Para incentivar este esquema, los est\u00edmulos que ofrezca el Gobierno deben ser consistentes con la capacidad fiscal del Estado y proporcionales al esfuerzo individual de los beneficiarios. As\u00ed mismo su dise\u00f1o debe ser muy cuidadoso para no propiciar la informalidad y evitar el retiro anticipado de recursos, salvo situaciones excepcionales\u201d105. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En la ponencia para segundo debate, contenida en la Gaceta del Congreso No. 418 del 3 de junio de 2009106, el texto anteriormente citado aparece de manera id\u00e9ntica. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ahora, en la Gaceta del Congreso No. 735 de 14 de agosto de 2009, que contiene el Acta 59 de la sesi\u00f3n ordinaria de la plenaria del Senado de la Rep\u00fablica, aparecen consignadas algunas intervenciones, tanto del Gobierno nacional, como de los diferentes senadores, y que resultan de gran importancia para la materia bajo estudio.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El ministro de Hacienda y Cr\u00e9dito P\u00fablico intervino en la plenaria para explicar y justificar la introducci\u00f3n de la regulaci\u00f3n de los BEPS, en desarrollo de lo dispuesto en el Acto Legislativo 01 de 2005. Este elemento de la reforma era, en sus palabras, el componente \u201cde mayor connotaci\u00f3n social\u201d 107 y se\u00f1al\u00f3 que la propuesta era \u201cs\u00f3lida, fiscalmente es sostenible y socialmente es responsable\u201d108. El ministro afirm\u00f3 que el art\u00edculo permit\u00eda \u201ccrear un sistema de ahorro para la vejez, dirigido inicialmente y con gran \u00e9nfasis a esos cerca de 9 millones de colombianos que hoy ganan menos de un salario m\u00ednimo, que est\u00e1n en la informalidad y que no tienen posibilidades de llegar al sistema pensional colombiano, dada la realidad de la pir\u00e1mide laboral y de las caracter\u00edsticas del mercado laboral en Colombia y esas personas el Estado tiene que pensar qu\u00e9 debe hacer con ellas, pues con esta propuesta lo que estamos dise\u00f1ando es un mecanismo de ahorro, voluntario, pero de ahorro\u201d109. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Igualmente, en el tr\u00e1mite legislativo intervino el Senador Jos\u00e9 Dar\u00edo Salazar Cruz quien, al apoyar la propuesta legislativa, indic\u00f3 que el esquema de multifondos le iba a \u201cpermitir a muchos colombianos de todas las edades que puedan a lo largo de su vida, tener mayores recaudos, mejores pensiones, y que m\u00e1s colombianos con el fortalecimiento de los fondos de pensiones en mejores condiciones se puedan pensionar\u201d110 y que los BEPS apuntaba a logar que \u201ccolombianos que no alcanzan a obtener una m\u00ednima pensi\u00f3n puedan obtener estos beneficios econ\u00f3micos\u201d111. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. As\u00ed, a lo largo del debate se encuentran varias intervenciones de senadores en las que se pronunciaron tanto a favor como en contra de las modificaciones al esquema de multifondos o de BEPS en el proyecto. Dos de estas intervenciones por parte de los senadores Luis Carlos Avellaneda Tarazona y H\u00e9ctor Hel\u00ed Rojas Jim\u00e9nez tocan de manera extensa el tema pensional en la reforma112. Con lo anterior, queda claro que el tema de la seguridad social en pensiones no era un asunto accidental en el proyecto de ley, sino un componente axial del mismo, que fue objeto de extenso debate por parte de los parlamentarios en los que tuvieron la oportunidad de expresar su apoyo o su desacuerdo sobre estos aspectos de la iniciativa legislativa, siendo uno de ellos la implementaci\u00f3n de los BEPS. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En consecuencia, los antecedentes del tr\u00e1mite legislativo dan cuenta del alcance de la iniciativa legislativa en la que, si bien es relevante la regulaci\u00f3n del sistema financiero, esta surte sus efectos en diversos sectores que dependen de ella para lograr sus objetivos, como es el de la seguridad social en pensiones. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El objetivo de la iniciativa era modificar y actualizar distintas normas aplicables a los sujetos que interact\u00faan en el mercado financiero, de seguros y de valores113, entre ellos la regulaci\u00f3n del sistema pensional, y uno de sus componentes el programa de BEPS. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Frente al texto de la ley finalmente aprobada, de su atenta lectura se comprueba que la mayor\u00eda, si no todas las dem\u00e1s disposiciones que integran el articulado de m\u00e1s de un centenar de disposiciones, incluso las que hacen parte del T\u00edtulo IX (otras disposiciones) versan sobre temas financieros, de seguros, operaciones autorizadas, intervenci\u00f3n e inspecci\u00f3n y vigilancia del Estado y otras materias relacionadas con las antes referidas. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Es importante resaltar que, a partir de la estructura de la ley, se evidencia una relaci\u00f3n estrecha entre las disposiciones de car\u00e1cter financiero y el concepto de seguridad social. Un componente significativo de la referida ley versa sobre aspectos relacionados con el funcionamiento del Sistema de Seguridad Social, sus aspectos financieros, su relaci\u00f3n con el r\u00e9gimen de protecci\u00f3n al consumidor financiero o con las instituciones que administran el sistema (arts. 14, 23, 24, 35, 42, 45 a 60, 87 y 97), as\u00ed como sobre el \u201cR\u00e9gimen de Protecci\u00f3n al Consumidor Financiero\u201d. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1. Examen de conexidad entre el contenido de la disposici\u00f3n demandada y el n\u00facleo tem\u00e1tico de la ley en la que ella se inserta \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el presente ac\u00e1pite, la Sala proceder\u00e1 a establecer si la disposici\u00f3n examinada, atendiendo a su contenido normativo, guarda conexidad con la materia de la ley de la que hace parte. Para este efecto, proceder\u00e1 a determinar el grado de rigurosidad con el que debe adelantar el examen de la norma acusada\u2013t\u00edtulo 5.2.1. infra\u2013, para luego efectuar el an\u00e1lisis de conexidad \u2013t\u00edtulo 5.2.2. infra\u2013. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. Rigor con el que debe adelantarse el juicio de unidad de materia en el presente asunto \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Conforme a lo expuesto en el t\u00edtulo 4.2. supra, el an\u00e1lisis que debe adelantar la Corte frente al presunto desconocimiento del principio de unidad de materia puede asumir diversos niveles de rigor. Al respecto, en la Sentencia C-896 de 2012 esta Corporaci\u00f3n resalt\u00f3:\u00a0 \u00a0 \u00a0<\/p>\n<p>\u201ccuando los prop\u00f3sitos que justifican el reconocimiento del principio de unidad de materia han sido satisfechos durante el debate legislativo, el rigor en el examen que debe adelantarse puede disminuir significativamente haciendo posible, en consecuencia, el empleo de criterios interpretativos m\u00e1s deferentes con la actividad legislativa. En efecto si una disposici\u00f3n con una conexi\u00f3n lejana a la materia del proyecto fue objeto de discusi\u00f3n y votaci\u00f3n a lo largo de todo el tr\u00e1mite legislativo y, en esa medida, alrededor de la misma se desarroll\u00f3 un adecuado proceso de deliberaci\u00f3n, el requerimiento de conexidad podr\u00e1 resultar menos exigente, en tanto ya se habr\u00eda controlado uno de los riesgos que pretende enfrentarse con el reconocimiento constitucional del principio de unidad de materia\u201d114. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. As\u00ed, a juicio de la Sala, dados los antecedentes legislativos rese\u00f1ados en el t\u00edtulo 5.1.1. supra, en el presente asunto hay lugar a desarrollar un juicio de conexidad de baja intensidad, concordante con la cl\u00e1usula general de competencia del legislador y con el principio democr\u00e1tico. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Este est\u00e1ndar se justifica, adem\u00e1s, en la forma en que se introdujo y aprob\u00f3 la disposici\u00f3n demandada en el tr\u00e1mite legislativo. En ese sentido, la propuesta normativa que concluy\u00f3 en el art. 87 acusado fue objeto de conocimiento por parte de los congresistas, e incluso del autor de la iniciativa legislativa, a tal punto que el ministro de Hacienda y Cr\u00e9dito P\u00fablico manifest\u00f3 ante los congresistas el apoyo del gobierno a la misma, y diversos legisladores se pronunciaron de manera tanto favorable como adversa a su contenido; lo que evidencia la satisfacci\u00f3n preponderante de la exigencia de deliberaci\u00f3n democr\u00e1tica. Estos elementos son un fuerte indicio de que la propuesta normativa no fue tramitada soslayando su debida discusi\u00f3n y deliberaci\u00f3n por parte de los legisladores en el foro democr\u00e1tico, de tal forma que se garantiz\u00f3 la transparencia y racionalidad en su tr\u00e1mite, valores aunados al principio de unidad de materia, en los t\u00e9rminos referidos en el t\u00edtulo 4.1 supra. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. El art. 87 de la Ley 1328 de 2009 no es contrario a las exigencias normativas del principio de unidad de materia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El art. 87 demandado contiene una vinculaci\u00f3n objetiva y razonable entre la materia dominante o el asunto general sobre el que versa la Ley 1328 de 2009 y la materia que dicho art\u00edculo desarrolla, guardando conexidad tem\u00e1tica entre su contenido normativo y el de la ley de la cual hace parte, por las siguientes razones. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Es cierto que el art. 87 de la Ley 1382 de 2009 contiene un elemento de la seguridad social, en la medida en que el programa BEPS es considerado como un componente de los servicios sociales complementarios del Sistema de Seguridad Social, tendiente a la protecci\u00f3n en la vejez115. Sin embargo, tambi\u00e9n lo es que el esquema operativo del programa se apoya fuertemente en aspectos financieros, ya que su prop\u00f3sito es servir como un sistema de ahorro y como un medio de aseguramiento, a tal punto que su prestaci\u00f3n principal funciona por medio de la contrataci\u00f3n de un seguro, con una entidad aseguradora autorizada para dicho efecto. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El programa se enfoca de manera primordial en fomentar el ahorro en cuentas individuales dentro del fondo com\u00fan de BEPS administrado por Colpensiones116, empresa industrial y comercial del Estado organizada como entidad financiera de car\u00e1cter especial117. El programa tiene como poblaci\u00f3n objetivo las personas de bajos recursos que por sus condiciones socioecon\u00f3micas no podr\u00edan llegar a cumplir con los requisitos legales para obtener una pensi\u00f3n, en los t\u00e9rminos regulados en el Sistema General de Pensiones118. El aspecto asistencial del programa corresponde, primordialmente, a un incentivo financiero al ahorro, que no es otra cosa que un subsidio peri\u00f3dico sobre el 20% de los aportes que realiza el sujeto vinculado al programa en su cuenta individual119. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Asimismo, la forma en que se materializa la anualidad vitalicia es por medio de la contrataci\u00f3n de un seguro, tal y como lo dispone el inciso 9\u00b0 del par\u00e1grafo \u00fanico del art\u00edculo demandado y lo reglamenta el art. 2.2.13.5.2. del Decreto 1833 de 2016. De igual modo, el programa cuenta con lo que se denomina un \u201cincentivo puntual\u201d, consistente en un subsidio para acceder a \u201cmicroseguros\u201d que garantizan el riesgo de invalidez y muerte del beneficiario, al que se refiere el inciso 6\u00ba del par\u00e1grafo \u00fanico del art. 87 acusado. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Es tambi\u00e9n posible inferir la connotaci\u00f3n financiera de la disposici\u00f3n demandada de su condici\u00f3n de instrumento de captaci\u00f3n de dineros del p\u00fablico, raz\u00f3n por la cual le corresponde a la Superintendencia Financiera la inspecci\u00f3n, vigilancia y control de la actividad, tal y como lo dispone el inciso 7\u00b0 del par\u00e1grafo \u00fanico de la disposici\u00f3n120. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Adicionalmente, es importante resaltar que en la Sentencia C-182 de 2020, esta Corte se pronunci\u00f3 acerca de la constitucionalidad del Decreto Legislativo 565 de 2020, en el que se definieron \u201creglas jur\u00eddicas que permitan atender el desbalance deficitario futuro entre el valor presente actuarial de la reserva matem\u00e1tica de las anualidades vitalicias de BEPS del mes anterior y el valor del portafolio a precios de mercado, con recursos del presupuesto asignado al Servicio Social Complementario de los Beneficios Econ\u00f3micos Peri\u00f3dicos BEPS\u201d, para garantizar el pago de las anualidades vitalicias de los BEPS. En la contextualizaci\u00f3n que en dicha sentencia se hizo acerca de este programa se precis\u00f3: \u00a0 \u00a0<\/p>\n<p>\u201cEn su concepci\u00f3n operativa, en consecuencia, los BEPS pueden entenderse tambi\u00e9n como desarrollo del art\u00edculo 335 de la Carta, al ser una expresi\u00f3n de la intervenci\u00f3n del Estado en la econom\u00eda, ya que los recursos del programa BEPS constituyen, en parte, captaciones de recursos provenientes del p\u00fablico, que junto con los rendimientos y el monto del incentivo obtenido por parte del Estado, le permiten al ahorrador beneficiado contratar un seguro que le pague peri\u00f3dicamente un monto b\u00e1sico de dinero que sea apoyo para su sostenimiento en la vejez. Por lo que se trata de capitales que, en virtud de la regulaci\u00f3n que hace el legislador, pueden ser administrados por las entidades autorizadas y vigiladas por la Superintendencia Financiera de Colombia para este prop\u00f3sito\u201d121. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. S\u00edntesis \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El demandante alega que el art\u00edculo 87 de la Ley 1328 de 2009 desconoce el principio de unidad de materia \u2013art\u00edculos 158 y 169 de la Constituci\u00f3n\u2013 y el principio de progresividad de la seguridad social \u2013art\u00edculo 48 de la Constituci\u00f3n\u2013. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En primer lugar, la Corte encuentra que el cargo formulado por el presunto desconocimiento del art. 48 de la Constituci\u00f3n, en relaci\u00f3n con el principio de progresividad y de no regresividad en materia de seguridad social, no es apto, al no satisfacer los m\u00ednimos argumentativos para proferir un fallo de fondo.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En segundo lugar, la Sala Plena evidencia la conexidad tem\u00e1tica entre el art\u00edculo acusado y la materia general de la Ley 1328 de 2009, ya que si bien la materia que regula se relaciona con la seguridad social \u2013al regular un servicio social complementario\u2013, tambi\u00e9n encuentra una conexidad objetiva y verificable con la materia financiera y aseguradora. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. DECISI\u00d3N \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Plena de la Corte Constitucional, administrando justicia en nombre del pueblo y por mandato de la Constituci\u00f3n, \u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>Declarar EXEQUIBLE el art\u00edculo 87 de la Ley 1328 de 2009, \u201cPor la cual se dictan normas en materia financiera, de seguros, del mercado de valores y otras disposiciones\u201d, por el cargo analizado. \u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese, publ\u00edquese y c\u00famplase, \u00a0<\/p>\n<p>ANTONIO JOS\u00c9 LIZARAZO OCAMPO \u00a0<\/p>\n<p>Presidente \u00a0<\/p>\n<p>DIANA FAJARDO RIVERA \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>-Ausente con permiso- \u00a0<\/p>\n<p>JORGE ENRIQUE IB\u00c1\u00d1EZ NAJAR \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>ALEJANDRO LINARES CANTILLO \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>PAOLA ANDREA MENESES MOSQUERA \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>GLORIA STELLA ORTIZ DELGADO \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>CRISTINA PARDO SCHLESINGER \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>JOS\u00c9 FERNANDO REYES CUARTAS \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>ALBERTO ROJAS R\u00cdOS \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0<\/p>\n<p>Secretaria General \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 Mediante auto de noviembre 3 de 2020, el magistrado sustanciador admiti\u00f3 la demanda, \u201cpor la presunta vulneraci\u00f3n de los art\u00edculos 4 y 48, 149, 158 y 169 de la Constituci\u00f3n\u201d, y mediante auto de 13 de enero de 2021 orden\u00f3 comunicar el inicio del proceso a los presidentes del Senado y de la C\u00e1mara de Representantes, as\u00ed como al ministro de Hacienda y Cr\u00e9dito P\u00fablico. Igualmente, dio traslado al Procurador General de la Naci\u00f3n y orden\u00f3 fijar en lista el proceso para que los ciudadanos intervinieran. Por \u00faltimo, invit\u00f3 a participar al Defensor del Pueblo; al ministro del Trabajo y al director Fondo de Solidaridad Pensional; al director del Programa de Beneficios Econ\u00f3micos Peri\u00f3dicos \u2013BEPS\u2013 de la Administradora Colombiana de Pensiones \u2013COLPENSIONES\u2013; a la Unidad Administrativa Especial de Organizaciones Solidarias; a la Central Unitaria de Trabajadores \u2013CUT\u2013; a la Asociaci\u00f3n Colombiana de Administradoras de Fondos de Pensiones y Cesant\u00edas \u2013ASOFONDOS\u2013; a la Asociaci\u00f3n Nacional de Empresarios de Colombia \u2013ANDI\u2013; al Colegio de Abogados del Trabajo; a la Confederaci\u00f3n General del Trabajo; a la Academia Colombiana de Jurisprudencia; al Departamento de Derecho Laboral de la Universidad Externado de Colombia; al Grupo de Investigaci\u00f3n Perspectivas y Problemas Contempor\u00e1neos del Derecho de Trabajo y la Seguridad Social de la Universidad Nacional de Colombia y al Grupo de Investigaci\u00f3n \u201cEstudios en Derecho Laboral y Seguridad Social\u201d de la Universidad Javeriana. \u00a0<\/p>\n<p>3 Demanda, fl. 6. \u00a0<\/p>\n<p>4 Ibid. \u00a0<\/p>\n<p>5 Ibid. \u00a0<\/p>\n<p>6 Demanda, fl. 16. \u00a0<\/p>\n<p>7 Demanda, fl. 18. \u00a0<\/p>\n<p>8 Ibid. \u00a0<\/p>\n<p>9 Ibid. \u00a0<\/p>\n<p>10 Ibid. \u00a0<\/p>\n<p>11 Ibid. \u00a0<\/p>\n<p>12 Cfr., los arts. 244 de la Constituci\u00f3n y 11 del Decreto 2067 de 1991. \u00a0<\/p>\n<p>13 A partir de esta idea, resalta que, \u201cfrente al contenido del principio de unidad de materia lo que cabe es una interpretaci\u00f3n razonable y proporcional, pues, aunque debe existir una conexi\u00f3n entre las disposiciones que integran el conjunto normativo y los n\u00facleos de su contenido, esta \u2018no debe ser directa ni estrecha, puede ser material, causal, teleol\u00f3gica o sistem\u00e1tica\u2019\u201d. Intervenci\u00f3n del Ministerio de Hacienda y Cr\u00e9dito P\u00fablico, fl. 7. \u00a0<\/p>\n<p>14 Ibid., fl. 8. \u00a0<\/p>\n<p>15 Ibid. \u00a0<\/p>\n<p>16 Ibid., fl. 11. \u00a0<\/p>\n<p>17 Ibid., fl. 22. \u00a0<\/p>\n<p>18 Ibid. \u00a0<\/p>\n<p>19 Ibid. \u00a0<\/p>\n<p>20 Cfr., el art. 13 del Decreto 2067 de 1991. \u00a0<\/p>\n<p>21 Intervenci\u00f3n Ministerio del Trabajo, fl. 6. \u00a0 \u00a0<\/p>\n<p>22 Ibid., fl. 7. \u00a0<\/p>\n<p>23 Ibid., fl. 8. \u00a0<\/p>\n<p>24 Ibid., fl. 11. \u00a0<\/p>\n<p>25 Intervenci\u00f3n de la Administradora Colombiana de Pensiones, folio 1. \u00a0<\/p>\n<p>26 Ibid., fl. 3. \u00a0<\/p>\n<p>27 Ibid., fl. 5. \u00a0<\/p>\n<p>28 Ibid. \u00a0<\/p>\n<p>29 En particular, resalta lo siguiente: \u201caquellos aspectos desarrollados en la norma acusada tendientes a determinar las personas que pueden ahorrar en el programa, la clase y condiciones de incentivos que se otorgar\u00e1n, los seguros que les ser\u00e1n conferidos, las condiciones de administraci\u00f3n de recursos mediante criterios de eficiencia y rentabilidad, la determinaci\u00f3n de un administrador de los recursos y de un ente particular asignado para su vigilancia &#8211; en este caso la Superintendencia Financiera -, se establecen como presupuestos de protecci\u00f3n del ahorro y del ahorrador en BEPS, en su calidad de consumidor financiero\u201d. Ibid., fl. 6. \u00a0<\/p>\n<p>30 Ibid., fl. 7. \u00a0<\/p>\n<p>31 Ibid. \u00a0<\/p>\n<p>33 Ibid. \u00a0<\/p>\n<p>34 Intervenci\u00f3n Asociaci\u00f3n Nacional de Empresarios de Colombia, folio 1.\u00a0 \u00a0<\/p>\n<p>35 Ibid.\u00a0 \u00a0<\/p>\n<p>36 Ibid., fl. 2. \u00a0<\/p>\n<p>37 Ibid. \u00a0<\/p>\n<p>38 La intervenci\u00f3n est\u00e1 suscrita por Jorge Eli\u00e9cer Manrique Villanueva, director del Departamento de Derecho Laboral; Jorge Mario Ben\u00edtez Pinedo, docente del Departamento de Derecho Laboral; Germ\u00e1n Ernesto Ponce Bravo, docente del Departamento de Derecho Laboral y Diego Alejandro S\u00e1nchez Acero, docente del Departamento de Derecho Laboral. \u00a0<\/p>\n<p>39 Intervenci\u00f3n del Departamento de Derecho Laboral de la Universidad Externado de Colombia, fl. 3. \u00a0<\/p>\n<p>40 Ibid., fl. 3. \u00a0<\/p>\n<p>41 Ibid.\u00a0 \u00a0<\/p>\n<p>42 Ibid., fl. 4.\u00a0 \u00a0<\/p>\n<p>43 Ibid. \u00a0<\/p>\n<p>44 Ibid. \u00a0<\/p>\n<p>45 Ibid., fl. 6. \u00a0<\/p>\n<p>46 Ibid., fl. 8. \u00a0<\/p>\n<p>47 Ibid., fl. 10. \u00a0<\/p>\n<p>48 Cfr., lo dispuesto en los arts. 242.2 de la Constituci\u00f3n y el art. 7 del Decreto 2067 de 1991. \u00a0<\/p>\n<p>49 Concepto de la Procuradora General de la Naci\u00f3n, fl. 5. \u00a0<\/p>\n<p>50 Ibid., fl. 6. \u00a0<\/p>\n<p>51 Cfr., entre otras, las sentencias C-634 de 1996, C-055 de 2010 y C-699 de 2016. \u00a0<\/p>\n<p>52 Sentencia C-1052 de 2001. En esta providencia la Corte sistematiz\u00f3 la jurisprudencia existente sobre el tema de los requisitos de procedibilidad de la acci\u00f3n de inconstitucionalidad. Este Tribunal ha definido el alcance de estas exigencias en los siguientes t\u00e9rminos: claridad, cuando existe un hilo conductor de la argumentaci\u00f3n que permite comprender el contenido de la demanda y las justificaciones en las cuales se soporta;\u00a0certeza, cuando la demanda recae sobre una proposici\u00f3n jur\u00eddica real y existente y no en una que el actor deduce de manera subjetiva, valga decir, cuando existe una verdadera confrontaci\u00f3n entre la norma legal y la norma constitucional;\u00a0especificidad, cuando se define o se muestra c\u00f3mo la norma demandada vulnera la Constituci\u00f3n;\u00a0pertinencia, cuando se emplean argumentos de naturaleza estrictamente constitucional y no de estirpe legal, doctrinal o de mera conveniencia; y\u00a0suficiencia, cuando la demanda tiene alcance persuasivo, esto es, cuando es capaz de despertar siquiera una duda m\u00ednima sobre la exequibilidad de la norma demandada. En id\u00e9ntico sentido, cfr., entre otras, las sentencias C-1052 de 2001, C-856 de 2005 y C-220 de 2019. \u00a0<\/p>\n<p>53 Sentencia C-277 de 2011, reiterada en la Sentencia C-121 de 2020. \u00a0<\/p>\n<p>54 En este sentido, las sentencias C-623 de 2008, C-894 de 2009, C-055 de 2013, C-281 de 2013 y C-165 de 2019. \u00a0<\/p>\n<p>55 Demanda, fl. 5. \u00a0<\/p>\n<p>56 Ibid. \u00a0<\/p>\n<p>57 La Sala considera pertinente precisar que la formulaci\u00f3n del cargo admitido se encuentra contenida en el literal c) del numeral 6 del cap\u00edtulo correspondiente al segundo cargo de la demanda, el cual se refiere de manera espec\u00edfica a la vulneraci\u00f3n del principio de progresividad. Esto, por cuanto, la elaboraci\u00f3n del segundo cargo por la presunta vulneraci\u00f3n del art. 48 de la Constituci\u00f3n, contenido en el numeral 6 de la demanda tiene varios literales: el literal a) se refiere a la presunta violaci\u00f3n de los arts. 114 y 150 de la Constituci\u00f3n; el literal b) trata sobre el presunto desconocimiento de los arts. 1, 2, 46, 48 y 365 de la Constituci\u00f3n y el literal d) versa sobre la presunta vulneraci\u00f3n de los arts. 48, 114, 150, 189 y 365. As\u00ed, conforme al auto de 26 de noviembre de 2020, el magistrado sustanciador rechaz\u00f3 \u201clos cargos por la presunta vulneraci\u00f3n de los art\u00edculos 1, 2, 5, 11, 13, 46, 53, 84, 93, 94, 114, 150, 189 y 365 Superiores; la Declaraci\u00f3n Universal de Derechos Humanos; los art\u00edculos 2, 9 y 11 del PIDESC; la Constituci\u00f3n de la OIT; los arts. 1 y 9 del Protocolo de San Salvador; el art\u00edculo 5, literal e) del Convenio Internacional sobre la Eliminaci\u00f3n de Todas las Formas de Discriminaci\u00f3n Racial; los art\u00edculos 1, 24, 26 y 29 de la CADH; los arts. 4 y 106 del C\u00f3digo Iberoamericano de Seguridad Social y la Declaraci\u00f3n de Filadelfia\u201d. \u00a0<\/p>\n<p>58 Demanda, fl. 18. \u00a0<\/p>\n<p>59 Ibid. \u00a0<\/p>\n<p>60 Ibid. \u00a0<\/p>\n<p>61 Ibid. \u00a0<\/p>\n<p>62 Ibid. \u00a0<\/p>\n<p>63 Sentencia C-1052 de 2001. \u00a0<\/p>\n<p>64 Sentencia C-213 de 2017. \u00a0<\/p>\n<p>65 Sentencia C-025 de 2020. \u00a0<\/p>\n<p>66 Sentencia C-644 de 2012.\u00a0 \u00a0<\/p>\n<p>67 Ibid. \u00a0<\/p>\n<p>68 Sentencia C-447 de 1997. \u00a0<\/p>\n<p>69 Sentencia C-025 de 1993.\u00a0 \u00a0<\/p>\n<p>71 Cfr., las sentencias C-025 de 1993, C-501 de 2001, C-551 de 2003, C-801 de 2003, C-1147 de 2003, C-305 de 2004, C-188 de 2006 y C-822 de 2011, entre otras. \u00a0 \u00a0<\/p>\n<p>72 En este sentido, las sentencias C-025 de 1993 y C-402 de 1997. \u00a0<\/p>\n<p>73 Cfr., al respecto, las sentencias C-523 de 1995, C-657 de 2000, C-501 de 2001, C-570 de 2003, C-230 de 2008, C-802 de 2009 y C-077 de 2012. \u00a0<\/p>\n<p>74 Al respecto, en la Sentencia C-803 de 2003, la Corte manifest\u00f3: \u201cLa Corte ha se\u00f1alado que el debate legislativo es la oportunidad de hacer efectivo el principio democr\u00e1tico en el proceso de formaci\u00f3n de la ley, en el que concurren y participan tanto minor\u00edas como mayor\u00edas, y que para el que el mismo pueda darse, es imprescindible que el objeto sobre el que recae, esto es el proyecto o la proposici\u00f3n de f\u00f3rmula normativa que va adoptarse, debe ser conocido de manera general por quienes deben discutirlo\u201d. \u00a0<\/p>\n<p>75 Ibid. En dicha providencia, la Corte precis\u00f3 que \u201cla unidad de materia contribuye a consolidar el principio de la seguridad jur\u00eddica porque, por un lado asegura la coherencia interna de las leyes, las cuales no obstante que pueden tener diversidad de contenidos tem\u00e1ticos, deben contar siempre con un n\u00facleo de referencia que les de unidad y que permita que sus disposiciones se interpreten de manera sistem\u00e1tica, y por otro, \u00a0evita que sobre la misma materia se multipliquen las disposiciones, en distintos cuerpos normativos, con el riesgo de que se produzcan inconsistencias, regulaciones ocultas e incertidumbre para los operadores jur\u00eddicos\u201d. \u00a0<\/p>\n<p>76 En este sentido, la Sentencia C-665 de 2016. \u00a0<\/p>\n<p>77 En la Sentencia C-995 de 2001, la Corte se\u00f1al\u00f3 que el constituyente pretendi\u00f3 evitar la proliferaci\u00f3n de iniciativas legislativas sin n\u00facleo tem\u00e1tico alguno, la inclusi\u00f3n y aprobaci\u00f3n de normas desvinculadas de las materias inicialmente reguladas, la promulgaci\u00f3n de leyes que se hubieren sustra\u00eddo a los debates legislativos y la emisi\u00f3n de disposiciones promovidas subrepticiamente por grupos interesados en ocultarlas a la opini\u00f3n p\u00fablica, como canal de expresi\u00f3n de la democracia. \u00a0<\/p>\n<p>78 Constituci\u00f3n Pol\u00edtica, art. 158: \u201c[\u2026] El presidente de la respectiva comisi\u00f3n rechazar\u00e1 las iniciativas que no se avengan con este precepto, pero sus decisiones ser\u00e1n apelables ante la misma comisi\u00f3n\u201d. \u00a0<\/p>\n<p>79 Al respecto cfr., las sentencias C-992 de 2001, C-188 de 2006, C-620 de 2016 y C-121 de 2020, entre muchas otras. \u00a0<\/p>\n<p>80 Sentencia C-285 de 2017.\u00a0 \u00a0<\/p>\n<p>81 Ibidem.\u00a0 \u00a0<\/p>\n<p>82 Sentencia C-400 de 2010. \u00a0<\/p>\n<p>83 Sentencia C-353 de 2017.\u00a0 \u00a0<\/p>\n<p>84 Sentencia C-142 de 2015. Seg\u00fan se se\u00f1ala en la Sentencia C-665 de 2016 para tales efectos es especialmente relevante valorar los antecedentes legislativos en relaci\u00f3n con la disposici\u00f3n objeto de control constitucional. \u00a0<\/p>\n<p>85 Cfr., al respecto, entre otras, lo se\u00f1alado en las sentencias C-047 de 2021, C-030 de 2021, C-440 de 2020, C-415 de 2020, C-068 de 2020, C-008 de 2018, C-453 de 2016, C-016 de 2016, C-801 de 2008, C-377 de 2008, C-795 de 2004 y C-305 de 2004. \u00a0<\/p>\n<p>86 Sentencia C-044 de 2017. \u00a0<\/p>\n<p>87 Sentencia C-704 de 2015.\u00a0 \u00a0<\/p>\n<p>88 Sentencia C-025 de 1993.\u00a0 \u00a0<\/p>\n<p>89 Sentencia C-142 de 2015: \u201cEn el contexto del proceso legislativo, que se caracteriza por el debate, las propuestas, las modificaciones y los ajustes a los textos normativos, no se puede asumir a la unidad de materia como una exigencia inflexible o r\u00edgida, al punto de convertirla en un obst\u00e1culo a dicho proceso. Tampoco se puede confundir la unidad de materia, que plantea una exigencia de orden y de coherencia, con la simplicidad tem\u00e1tica del proyecto\u201d. \u00a0<\/p>\n<p>90 Cfr. Sentencias C-400 de 2010 y C-201 de 2015, en esta \u00faltima se reitera la Sentencia C-501 de 2001.\u00a0 \u00a0<\/p>\n<p>91 Sentencia C-540 de 2001. \u00a0<\/p>\n<p>92 Sentencia C-147 de 2015. \u00a0<\/p>\n<p>93 Sentencia C-523 de 1995. \u00a0<\/p>\n<p>94 En id\u00e9ntico sentido, las sentencias C-188 de 2006, C-432 de 2010 y C-830 de 2013. \u00a0<\/p>\n<p>95 Gaceta del Congreso de la Rep\u00fablica No. 138 de 11 de abril de 2008, p. 13. \u00a0<\/p>\n<p>96 Ibid. \u00a0<\/p>\n<p>97 Ibid. \u00a0<\/p>\n<p>98 Ibid., p. 15. \u00a0<\/p>\n<p>99 Igualmente, en relaci\u00f3n con este T\u00edtulo II, la exposici\u00f3n de motivos se\u00f1ala que otros de los objetivos de la facultad de intervenci\u00f3n del Gobierno nacional es la \u201cPromoci\u00f3n del acceso a servicios financieros por parte de la poblaci\u00f3n de menores recursos, as\u00ed como la peque\u00f1a, mediana y microempresa\u201d (ibid., p. 16). Al respecto, se indica: \u201cEl Gobierno Nacional ha entendido que el acceso al cr\u00e9dito y dem\u00e1s servicios financieros de las familias genera un c\u00edrculo virtuoso para la econom\u00eda pues contribuye a generar riqueza, al posibilitar que los agentes econ\u00f3micos e individuos emprendedores puedan explotar oportunidades productivas, generando fuentes de ingresos estables. || Esto indica la voluntad decidida de extender los servicios bancarios a un n\u00famero cada vez m\u00e1s alto de usuarios y, en particular, a los estratos de menores ingresos, de manera que puedan obtenerse las ventajas que brinda la banca contempor\u00e1nea, fundada en una tecnolog\u00eda de punta. [\u2026] || Cuentas simplificadas, formas sencillas para que la comunidad comience a conocer el servicio de la banca, disfrute sus beneficios e incluso se acerque a ella con una actitud positiva que contraste con la que en los \u00faltimos a\u00f1os se ha generado, seguramente de manera injustificada, pero ciertamente extendida. Este es un prop\u00f3sito del cual todos deber\u00edamos salir ganadores y es una labor en la cual, la banca, al extender sus servicios a otros segmentos de usuarios, cumple de mejor manera su responsabilidad social en un pa\u00eds en el cual, como se ha dicho afortunadamente por la Corte Suprema de Justicia, el cr\u00e9dito debe considerarse como un bien social. As\u00ed las cosas, el proyecto dota al Gobierno Nacional de instrumentos de intervenci\u00f3n que propendan por el logro de estos objetivos\u201d. \u00a0<\/p>\n<p>100 Ibid., p. 19. \u00a0<\/p>\n<p>101 Gaceta del Congreso, No. 341 del 10 de junio de 2008, p. 1. \u00a0<\/p>\n<p>102 Ibid., p. 3. \u00a0<\/p>\n<p>103 Ibid. \u00a0<\/p>\n<p>104 Ibid., p. 7. \u00a0<\/p>\n<p>105 Ibid., p. 20. \u00a0<\/p>\n<p>106 P. 31.\u00a0 \u00a0<\/p>\n<p>107 Gaceta del Congreso No. 735 de 14 de agosto de 2009, p. 49.\u00a0 \u00a0<\/p>\n<p>108 Ibid. \u00a0<\/p>\n<p>109 Ibid. \u00a0<\/p>\n<p>110 Ibid., p. 59. \u00a0<\/p>\n<p>111 Ibid. \u00a0<\/p>\n<p>112 Ibid., pp. 59 a 64. \u00a0<\/p>\n<p>113 Para tales efectos, es importante precisar que el t\u00edtulo del proyecto de ley originalmente propuesto,\u00a0\u201cPor la cual se dictan normas en materia financiera, de seguros, del mercado de valores y se dictan otras disposiciones\u201d, fue id\u00e9ntico al finalmente asignado a Ley 1328 de 2009. \u00a0<\/p>\n<p>114 Sentencia C-896 de 2012. \u00a0<\/p>\n<p>115 En relaci\u00f3n con este aspecto, el art. 2 del Decreto 604 de 2013, que reglament\u00f3 la disposici\u00f3n que ahora se demanda dispone: \u201cLos Beneficios Econ\u00f3micos Peri\u00f3dicos son un mecanismo individual, independiente, aut\u00f3nomo y voluntario de protecci\u00f3n para la vejez, que se ofrece como parte de los Servicios Sociales Complementarios y que se integra al Sistema de Protecci\u00f3n a la Vejez, con el fin de que las personas de escasos recursos que participen en este mecanismo obtengan hasta su muerte un ingreso peri\u00f3dico, personal e individual\u201d. \u00a0<\/p>\n<p>116 Decreto 1833 de 2016, art. 2.2.13.3.2. Registro y Contabilizaci\u00f3n de Aportes Servicio Social Complementario BEPS. \u00a0<\/p>\n<p>118 \u00a0En relaci\u00f3n con este aspecto, en el Documento Conpes Social No. 156 de 11 de septiembre de 2012 se se\u00f1ala: \u201cLos participantes en el esquema de BEPS al final de su vida laboral obtendr\u00e1n un Beneficio Econ\u00f3mico Peri\u00f3dico en su vejez basado en su esfuerzo de ahorro y un subsidio monetario otorgado por el Estado con el objetivo de mejorar las condiciones de vida de los adultos mayores m\u00e1s vulnerables. [\u2026] Dado que la participaci\u00f3n en el esquema de BEPS es voluntaria y flexible en cuant\u00eda y periodicidad, los incentivos por parte del Estado deben considerar el esfuerzo de ahorro de cada persona, fomentando la fidelidad y la participaci\u00f3n de la poblaci\u00f3n en la realizaci\u00f3n de este ahorro para la vejez, mediante incentivos al ahorro e incentivos a la fidelidad o puntuales\u201d. \u00a0<\/p>\n<p>119 En estos t\u00e9rminos, el art. 2.2.13.4.1. \u201cIncentivo Peri\u00f3dico\u201d, del Decreto 1833 de 2016.\u00a0 \u00a0<\/p>\n<p>120 Este dispone: \u201cLos recursos acumulados por los ahorradores de este programa constituyen captaciones de recursos del p\u00fablico; por tanto, el mecanismo de ahorro al que se hace referencia en este art\u00edculo ser\u00e1 administrado por las entidades autorizadas y vigiladas por la Superintendencia Financiera de Colombia\u201d \u00a0<\/p>\n<p>121 Sentencia C-182 de 2020. \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0\u00a0 Sentencia C-215\/21\u00a0 \u00a0 PRINCIPIO DE UNIDAD DE MATERIA-No vulneraci\u00f3n\/PRINCIPIO DE UNIDAD DE MATERIA-Conexidad tem\u00e1tica \u00a0 (\u2026) este programa de asistencia social a la vejez se encuentra (i) dentro de la tem\u00e1tica que regula el T\u00edtulo VI de la Ley 1328 de 2009, sobre el \u201cR\u00e9gimen Financiero de los Fondos de Pensi\u00f3n Obligatoria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[132],"tags":[],"class_list":["post-27828","post","type-post","status-publish","format-standard","hentry","category-sentencias-2021"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/27828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=27828"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/27828\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=27828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=27828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=27828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}