{"id":28141,"date":"2024-07-02T21:48:49","date_gmt":"2024-07-02T21:48:49","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/07\/02\/t-394-21-2\/"},"modified":"2024-07-02T21:48:49","modified_gmt":"2024-07-02T21:48:49","slug":"t-394-21-2","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-394-21-2\/","title":{"rendered":"T-394-21"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia T-394\/21 \u00a0<\/p>\n<p>DERECHO A LA SALUD Y A LA VIDA-Vulneraci\u00f3n cuando se hace nugatorio el derecho al diagn\u00f3stico \u00a0<\/p>\n<p>DERECHO A LA SALUD DE PERSONA DE LA TERCERA EDAD-Vulneraci\u00f3n por EPS por omisi\u00f3n en la autorizaci\u00f3n y suministro de insumos y tecnolog\u00edas \u00a0<\/p>\n<p>PRINCIPIO DE SUBSIDIARIEDAD COMO REQUISITO DE PROCEDIBILIDAD DE LA ACCION DE TUTELA-Procedencia dada la menor eficacia del mecanismo judicial ante la Superintendencia Nacional de Salud previsto en la ley 1122 de 2007 \u00a0<\/p>\n<p>DERECHO A LA SALUD-Doble connotaci\u00f3n al ser un derecho fundamental y al mismo tiempo un servicio p\u00fablico \u00a0<\/p>\n<p>DERECHO FUNDAMENTAL A LA SALUD-Elementos y principios \u00a0<\/p>\n<p>DERECHO A LA SALUD DEL ADULTO MAYOR-Protecci\u00f3n reforzada por ser sujeto de especial protecci\u00f3n constitucional \u00a0<\/p>\n<p>PRINCIPIO DE INTEGRALIDAD DEL DERECHO A LA SALUD-Casos en que procede la orden de tratamiento integral \u00a0<\/p>\n<p>SUMINISTRO DE TECNOLOGIAS Y SERVICIOS INCLUIDOS EN EL PLAN DE BENEFICIOS EN SALUD-Procedencia de la tutela cuando no existe prescripci\u00f3n m\u00e9dica y posterior ratificaci\u00f3n del m\u00e9dico tratante \u00a0<\/p>\n<p>DERECHO AL DIAGNOSTICO COMO PARTE DEL DERECHO A LA SALUD-Reglas para acceder a servicios o tecnolog\u00edas en salud como pa\u00f1ales, pa\u00f1itos h\u00famedos, cremas anti-escaras, silla de ruedas, entre otros \u00a0<\/p>\n<p>GARANT\u00cdA DE ACCESO AL SERVICIO DE TRANSPORTE INTRAURBANO O INTRAMUNICIPAL DE PACIENTES Y ACOMPA\u00d1ANTES EN EL SISTEMA DE SALUD-Reglas jurisprudenciales \u00a0<\/p>\n<p>DERECHO A LA SALUD-Suministro domiciliario del servicio de enfermer\u00eda en el nuevo Plan de Beneficios en Salud \u00a0<\/p>\n<p>SUMINISTRO DE INSUMOS, SERVICIOS Y TECNOLOGIAS EXCLUIDOS DEL PLAN DE BENEFICIOS EN SALUD-Reglas jurisprudenciales para no aplicar la exclusi\u00f3n \u00a0<\/p>\n<p>DERECHO A LA SALUD DE PERSONA DE LA TERCERA EDAD-Suministro de todos los insumos, elementos y servicios que se relacionen con su patolog\u00eda en la cantidad y condiciones que determine el m\u00e9dico tratante \u00a0<\/p>\n<p>DERECHO A LA SALUD Y A LA VIDA EN CONDICIONES DIGNAS-Orden a EPS realizar una valoraci\u00f3n m\u00e9dica sobre el estado de salud de la agenciada y autorizar el suministro de insumos dependiendo de la necesidad que evidencie el m\u00e9dico tratante \u00a0<\/p>\n<p>Referencia: Expediente T-8.111.691. \u00a0<\/p>\n<p>Acci\u00f3n de tutela instaurada por Fraddy Corredor Morales, en calidad de agente oficiosa de la se\u00f1ora Ana Elvia Morales de Corredor, en contra de FAMISANAR EPS. \u00a0<\/p>\n<p>Procedencia: Juzgado Veintitr\u00e9s Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1. \u00a0<\/p>\n<p>Asunto: Protecci\u00f3n constitucional reforzada a las personas de la tercera edad, derechos a la salud, a la vida digna y al diagn\u00f3stico.\u00a0 \u00a0<\/p>\n<p>Magistrada Sustanciadora: \u00a0<\/p>\n<p>GLORIA STELLA ORTIZ DELGADO. \u00a0<\/p>\n<p>Bogot\u00e1, D. C., dieciocho (18) de noviembre de dos mil veintiuno (2021). \u00a0<\/p>\n<p>La Sala Sexta de Revisi\u00f3n de la Corte Constitucional, integrada por el Magistrado Jos\u00e9 Fernando Reyes Cuartas y por las Magistradas Cristina Pardo Schlesinger y Gloria Stella Ortiz Delgado, quien la preside, en ejercicio de sus competencias constitucionales y legales, ha proferido la siguiente \u00a0<\/p>\n<p>SENTENCIA \u00a0<\/p>\n<p>En el tr\u00e1mite de revisi\u00f3n del fallo emitido el 29 de julio de 2021, por el Juzgado Veintitr\u00e9s Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1, que tutel\u00f3 los derechos fundamentales a la salud y a la vida en condiciones dignas, en la faceta de acceso al diagn\u00f3stico de la accionante.\u00a0 \u00a0<\/p>\n<p>El asunto lleg\u00f3 a la Corte, inicialmente, por remisi\u00f3n que efectu\u00f3 la mencionada autoridad judicial, en cumplimiento de lo dispuesto en el art\u00edculo 31 del Decreto 2591 de 19911. Lo anterior, para la revisi\u00f3n del fallo de instancia proferido el 4 de marzo de 2020, que neg\u00f3 la acci\u00f3n de tutela formulada por Fraddy Corredor Morales, en calidad de agente oficiosa. El expediente fue escogido para revisi\u00f3n por la Sala Cuarta de Selecci\u00f3n mediante auto del 16 de abril de 20212. El 3 de mayo siguiente, la Secretar\u00eda General remiti\u00f3 el expediente al despacho de la Magistrada Sustanciadora para lo de su competencia.\u00a0 \u00a0<\/p>\n<p>En sede de revisi\u00f3n, mediante Auto 318 del 22 de junio de 20213, la Sala Sexta declar\u00f3 la nulidad del tr\u00e1mite surtido despu\u00e9s del fallo de primera instancia por pretermisi\u00f3n de la segunda. En ese sentido, dej\u00f3 sin efectos las actuaciones surtidas en el proceso de la referencia, a partir del Oficio No. 225 del 13 de marzo de 20204, inclusive y orden\u00f3 que se tramite la segunda instancia. En todo caso, mantuvo la validez jur\u00eddica de las actuaciones surtidas en sede de revisi\u00f3n, relacionadas con la selecci\u00f3n del caso y las pruebas recaudadas. De esta forma, orden\u00f3 a la autoridad judicial competente que, una vez fallado el caso en segunda instancia, remitiera el expediente directamente al despacho de la Magistrada Sustanciadora para su revisi\u00f3n. \u00a0<\/p>\n<p>Despu\u00e9s de otra nulidad, ahora declarada por el juez de segunda instancia, el 29 de julio de 2021, el Juzgado Veintitr\u00e9s Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 profiri\u00f3 sentencia de \u00fanica instancia. En esa oportunidad, ampar\u00f3 los derechos a la salud y a la vida en condiciones dignas, en su faceta de acceso al diagn\u00f3stico de la accionante.\u00a0 \u00a0<\/p>\n<p>El 13 de agosto de 2021, la autoridad judicial remiti\u00f3 el expediente nuevamente para su revisi\u00f3n, de conformidad con las \u00f3rdenes proferidas por la Sala Sexta de Revisi\u00f3n en el Auto 318 del 22 de junio de 2021. As\u00ed, el 30 de agosto de 2021, la Secretar\u00eda General de esta Corporaci\u00f3n remiti\u00f3 el expediente al despacho de la Magistrada Sustanciadora. \u00a0<\/p>\n<p>ANTECEDENTES \u00a0<\/p>\n<p>El 20 de febrero de 2020, la se\u00f1ora Fraddy Corredor Morales, en calidad de agente oficiosa de la se\u00f1ora Ana Elvia Morales de Corredor, present\u00f3 acci\u00f3n de tutela en contra de FAMISANAR EPS. Consider\u00f3 que la accionada vulner\u00f3 los derechos a la vida digna, a la salud, a la vida y de petici\u00f3n de la agenciada5. Lo anterior, porque la EPS le neg\u00f3 la prestaci\u00f3n de los servicios de enfermer\u00eda o auxiliar de enfermer\u00eda 24 horas diarias y de transporte especial o ambulancia, as\u00ed como el suministro de silla de ruedas, pa\u00f1itos h\u00famedos, crema antipa\u00f1alitis, crema anti-escaras y crema para piel diab\u00e9tica. Por tal raz\u00f3n, solicit\u00f3 al juez constitucional ordenar la prestaci\u00f3n de los servicios requeridos, el suministro de los elementos m\u00e9dicos solicitados y, el tratamiento integral para sus patolog\u00edas6.\u00a0 \u00a0<\/p>\n<p>Hechos y pretensiones \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La se\u00f1ora Ana Elvia Morales de Corredor tiene 86 a\u00f1os7. Seg\u00fan la historia cl\u00ednica aportada en sede de revisi\u00f3n, padece de demencia por la enfermedad de Alzheimer at\u00edpica o de tipo mixto, diabetes mellitus, osteoartrosis, hipertensi\u00f3n arterial, constipaci\u00f3n, incontinencia mixta, fractura de cadera bilateral, catarata en ojo izquierdo y presenta secuelas de enfermedad cardiovascular. Adicionalmente, es usuaria de ox\u00edgeno domiciliario y depende por completo de un tercero para desarrollar sus actividades diarias como ba\u00f1arse, alimentarse y vestirse8. El 10 de diciembre de 2019, la accionante fue valorada por la IPS Fundaci\u00f3n Arc\u00e1ngeles. Como consecuencia de ese diagn\u00f3stico, FAMISANAR EPS certific\u00f3 que presenta discapacidad mental, f\u00edsica y m\u00faltiple de grado profundo9.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La agenciada est\u00e1 afiliada a FAMISANAR EPS10. Adicionalmente, pertenece al programa de m\u00e9dico domiciliario de la entidad11. Por esa raz\u00f3n, entre diciembre de 2018 y junio de 2019, la IPS Hospital en Casa atendi\u00f3 a la tutelante en su domicilio. Posteriormente, la IPS Emanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S asumi\u00f3 la prestaci\u00f3n de ese servicio12. \u00a0 \u00a0<\/p>\n<p>1. El n\u00facleo familiar de la accionante est\u00e1 conformado por su esposo, su hermana, su hija y sus dos nietos menores de edad13. El esposo (de 97 a\u00f1os) y la hermana (de 87 a\u00f1os) son personas de la tercera edad con afectaciones serias en su salud14.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Seg\u00fan la agente oficiosa, la titular de los derechos requiere los servicios de enfermer\u00eda o auxiliar de enfermer\u00eda 24 horas diarias y de transporte especial o ambulancia. Tambi\u00e9n, el suministro de silla de ruedas, pa\u00f1itos h\u00famedos, crema antipa\u00f1alitis, crema anti-escaras y crema para piel diab\u00e9tica. Sin embargo, los m\u00e9dicos tratantes de la IPS Emanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S no ordenaron la prestaci\u00f3n de los servicios, ni la entrega de los insumos mencionados. En su criterio, la omisi\u00f3n de los profesionales de la salud obedece a una pol\u00edtica interna de FAMISANAR EPS15.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por esta raz\u00f3n, su hija, quien hace las veces de agente oficiosa en este proceso, expres\u00f3 que dej\u00f3 de trabajar para dedicarse al cuidado de tiempo completo de su n\u00facleo familiar16. No obstante, uno de sus hijos recientemente present\u00f3 afectaciones en su proceso de aprendizaje. El servicio de orientaci\u00f3n de la instituci\u00f3n educativa a la que pertenece, lo remiti\u00f3 a dos entidades para que reciba tratamiento oportuno17. Esta situaci\u00f3n requiere que la agente salga de su vivienda para acompa\u00f1ar al ni\u00f1o a los tratamientos correspondientes. En consecuencia, le es imposible continuar a cargo del cuidado de su madre18.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ante la dif\u00edcil situaci\u00f3n que afronta, la agente solicit\u00f3 directamente a FAMISANAR EPS la prestaci\u00f3n del servicio de enfermer\u00eda domiciliaria 24 horas para su madre19. Sin embargo, el 4 de diciembre de 2019, la accionada neg\u00f3 la petici\u00f3n, porque ese servicio no fue ordenado por el m\u00e9dico tratante. Por el contrario, el profesional de la salud encargado report\u00f3 en la historia cl\u00ednica de la accionante que no tiene criterios para prescribir ese servicio20. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 25 de enero de 2020, la tutelante present\u00f3 una nueva petici\u00f3n a FAMISANAR EPS. En ella, solicit\u00f3 que realizaran los correctivos necesarios para que la IPS correspondiente atienda las patolog\u00edas de su madre con \u00e9tica profesional y calidez humana. Tambi\u00e9n, requiri\u00f3 que les permitan a los m\u00e9dicos tratantes ordenar los servicios y tecnolog\u00edas de salud que la paciente requiere. Esto, sin importar si est\u00e1n o no incluidas en el POS, hoy Plan de Beneficios en Salud (en adelante PBS). Y, finalmente, que le expliquen las razones por las cuales la EPS no puede asumir el costo de los procedimientos m\u00e9dicos que su madre requiere para mantener una vida digna21. Al momento de la presentaci\u00f3n de la tutela, la EPS no hab\u00eda contestado el mencionado requerimiento22.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El 26 de enero de 2020, la agenciada sufri\u00f3 una ca\u00edda que agrav\u00f3 su situaci\u00f3n. Este accidente le ocasion\u00f3 una fractura en el f\u00e9mur izquierdo. Por esa raz\u00f3n, fue sometida a una intervenci\u00f3n quir\u00fargica23. Su hija asegura que el accidente ocurri\u00f3 por la falta de prestaci\u00f3n del servicio de enfermer\u00eda solicitado24. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En vista de lo anterior, la agente interpuso acci\u00f3n de tutela en contra de FAMISANAR EPS. En su criterio, la entidad accionada vulner\u00f3 los derechos fundamentales de su madre a la vida digna y a la salud. Lo anterior, porque la entidad neg\u00f3 los servicios m\u00e9dicos de enfermer\u00eda 24 horas y de transporte especial y\/o ambulancia, el suministro de silla de ruedas, pa\u00f1itos h\u00famedos, crema antipa\u00f1alitis, crema anti-escaras y crema para piel diab\u00e9tica. A su juicio, esta situaci\u00f3n afecta el derecho a la salud de su madre en forma tal que pone en riesgo su vida25.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por esa raz\u00f3n, solicit\u00f3: (i) tutelar los derechos fundamentales invocados. En consecuencia, (ii) ordenar a la entidad accionada que autorice la totalidad de los servicios m\u00e9dicos mencionados; y, (iii) brinde, de manera oportuna, un tratamiento integral a la agenciada para mitigar las secuelas de sus patolog\u00edas. Tambi\u00e9n, pidi\u00f3 (iii) autorizar el recobro correspondiente a la Administradora de Recursos del Sistema General de Seguridad Social en Salud (en adelante ADRES); y, (iv) advertir a FAMISANAR EPS que no debe incurrir en hechos similares so pena de las sanciones previstas en el Decreto 2591 de 199126. \u00a0 \u00a0<\/p>\n<p>Actuaciones en sede de tutela \u00a0<\/p>\n<p>Mediante Auto del 21 de febrero de 2020, el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 admiti\u00f3 la acci\u00f3n de tutela. En esa oportunidad, ofici\u00f3 al representante legal de FAMISANAR EPS para garantizarle su derecho de contradicci\u00f3n. Asimismo, vincul\u00f3 a la IPS Emmanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S., con el fin de integrar el contradictorio27.\u00a0 \u00a0<\/p>\n<p>Respuesta de FAMISANAR EPS \u00a0<\/p>\n<p>El 27 de febrero de 2020, la accionada afirm\u00f3 que no vulner\u00f3 los derechos de la accionante por tres razones. En primer lugar, porque ha autorizado todos los tratamientos ordenados a la paciente. Expuso que, en virtud de la ley, solo puede autorizar los servicios y tecnolog\u00edas ordenados por profesionales de la salud. En este caso, los m\u00e9dicos tratantes no han prescrito los insumos, ni los servicios solicitados por la agente oficiosa28. De manera que no los puede suministrar29.\u00a0 \u00a0<\/p>\n<p>En segundo lugar, manifest\u00f3 que la EPS no tiene una pol\u00edtica que proh\u00edba a los m\u00e9dicos tratantes ordenar ciertos tratamientos. Asegur\u00f3 que los profesionales de la salud tienen plena autonom\u00eda en la atenci\u00f3n de sus pacientes30. Adicionalmente, afirm\u00f3 que estos profesionales no est\u00e1n adscritos a esa entidad. Por el contrario, hacen parte de la IPS Emmanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S. De manera que es imposible que la entidad les imponga criterios de atenci\u00f3n que afecten la prestaci\u00f3n del servicio31. \u00a0<\/p>\n<p>En tercer lugar, manifest\u00f3 que no hay lugar a conceder un tratamiento integral. En su criterio, esa solicitud versa sobre hechos futuros e inciertos. Adicionalmente, afirm\u00f3 que, seg\u00fan la jurisprudencia constitucional, es el m\u00e9dico tratante quien debe ordenar el tratamiento que corresponde al paciente. En ese sentido, el juez de tutela no puede prescribir el tratamiento, ni prever asuntos relacionados con prestaciones futuras32.\u00a0 \u00a0<\/p>\n<p>Finalmente, la demandada solicit\u00f3 que se nieguen las pretensiones del escrito de tutela. De manera subsidiaria, pidi\u00f3 que, en caso de conceder el amparo, se le autorice el recobro al ADRES de los costos que ocasionen los suministros solicitados33. \u00a0<\/p>\n<p>Por su parte, la IPS Emmanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S. guard\u00f3 silencio.\u00a0 \u00a0<\/p>\n<p>Decisiones de instancia \u00a0<\/p>\n<p>Sentencia de primera instancia \u00a0<\/p>\n<p>En Sentencia del 4 de marzo de 2020, el juez de primera instancia NEG\u00d3 el amparo de los derechos de la accionante. En esa oportunidad, consider\u00f3 que, de conformidad con la jurisprudencia constitucional, la EPS debe prestar los servicios ordenados por el m\u00e9dico tratante. En este caso, los profesionales de la salud encargados no prescribieron los servicios y tecnolog\u00edas de salud que solicita la agente oficiosa34. Por el contrario, el juez advirti\u00f3 que la accionada tramit\u00f3 todas las \u00f3rdenes m\u00e9dicas correspondientes. Por lo tanto, a su juicio, la EPS no incurri\u00f3 en conductas que vulneren los derechos de la agenciada35. Adicionalmente, asegur\u00f3 que ordenar la prestaci\u00f3n de un tratamiento integral implicar\u00eda suponer una vulneraci\u00f3n futura. En otras palabras, conllevar\u00eda a la protecci\u00f3n de un derecho que no ha sido vulnerado36.\u00a0 \u00a0<\/p>\n<p>El 6 de marzo de 2020, la agente oficiosa impugn\u00f3 la decisi\u00f3n referida con anterioridad. Por un lado, reiter\u00f3 los argumentos presentados en la demanda. Por el otro, expuso que la simple autorizaci\u00f3n de los servicios no es suficiente para garantizar el derecho a la salud de las personas. Afirm\u00f3 que, si el paciente no puede trasladarse para acceder a los servicios, la vulneraci\u00f3n del derecho permanece. En ese sentido, solicit\u00f3 al juez de segunda instancia: (i) revocar la decisi\u00f3n del A-quo y (ii) ordenar los servicios reiteradamente solicitados37.\u00a0 \u00a0<\/p>\n<p>A pesar de lo anterior, mediante Oficio No. 225 del 13 de marzo de 2020, el juez de primera instancia remiti\u00f3 el expediente a la Corte Constitucional. La Sala Cuarta de Selecci\u00f3n lo escogi\u00f3 para revisi\u00f3n, a trav\u00e9s del Auto del 16 de abril de 2021.\u00a0 \u00a0<\/p>\n<p>Actuaciones en sede de revisi\u00f3n \u00a0<\/p>\n<p>El despacho sustanciador advirti\u00f3 que el \u00faltimo documento que constaba en el expediente era una impugnaci\u00f3n. De manera que, en el proceso no se encontraba el tr\u00e1mite de la segunda instancia. En consecuencia, mediante Auto del 18 de mayo de 2021, solicit\u00f3 al Juzgado Veintitr\u00e9s Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 informaci\u00f3n sobre el tr\u00e1mite que surti\u00f3 el recurso de apelaci\u00f3n propuesto por la accionante el 6 de marzo de 2020. \u00a0<\/p>\n<p>El 21 de mayo de 2021, el juzgado requerido respondi\u00f3 preliminarmente a la solicitud38. Se\u00f1al\u00f3 que el expediente hab\u00eda sido remitido para el tr\u00e1mite de segunda instancia por medio del Oficio 225 del 13 de marzo de 202039. Sin embargo, mediante Oficio N\u00b0232 del 24 de mayo de 2021, rectific\u00f3 su respuesta. Manifest\u00f3 que, debido a un error secretarial, la impugnaci\u00f3n no se tramit\u00f3 en debida forma40. \u00a0<\/p>\n<p>Asimismo, adjunt\u00f3 un auto de la misma fecha, proferido por ese despacho, en el que: (i) concedi\u00f3 el recurso de apelaci\u00f3n; (ii) remiti\u00f3 el expediente electr\u00f3nico para reparto entre los Juzgados Penales del Circuito de Conocimiento de Bogot\u00e1; y, (iii) solicit\u00f3 a la Magistrada Sustanciadora que devolviera el cuaderno original del proceso, para tramitar la segunda instancia. Adem\u00e1s, (iv) manifest\u00f3 que adelantar\u00eda las acciones correccionales y disciplinarias correspondientes41. \u00a0<\/p>\n<p>En atenci\u00f3n a la remisi\u00f3n del expediente por parte del juez de instancia, la Oficina de Apoyo Judicial de Paloquemao someti\u00f3 la impugnaci\u00f3n a reparto el 24 de mayo de 202142. Por ese motivo, su estudio le correspondi\u00f3 al Juzgado 18 Penal del Circuito con Funci\u00f3n de Conocimiento. \u00a0<\/p>\n<p>Decreto de nulidad del tr\u00e1mite de tutela por pretermisi\u00f3n de instancia \u00a0<\/p>\n<p>En atenci\u00f3n a la situaci\u00f3n descrita, en Auto 318 del 22 de junio de 202143, la Sala Sexta de Revisi\u00f3n declar\u00f3 la nulidad por pretermisi\u00f3n de la segunda instancia. Por tal raz\u00f3n, dej\u00f3 sin efectos las actuaciones surtidas en el proceso de la referencia, a partir del Oficio No. 225 del 13 de marzo de 202044, inclusive. En todo caso, mantuvo la validez jur\u00eddica de las actuaciones surtidas en sede de revisi\u00f3n, relacionadas con la selecci\u00f3n del caso y las pruebas recaudadas45. De esta forma, orden\u00f3 a la autoridad judicial competente, una vez fallado el caso en segunda instancia, remitir el expediente directamente al despacho de la Magistrada Sustanciadora para su revisi\u00f3n. \u00a0<\/p>\n<p>El 1\u00ba de julio de 2021, la Secretar\u00eda General de la Corte remiti\u00f3 el expediente digital a la Oficina de Apoyo Judicial de Paloquemao de los Jueces Penales del Circuito de Bogot\u00e146. De igual manera, comunic\u00f3 la decisi\u00f3n al juez de primera instancia47 y a las partes. En atenci\u00f3n a la comunicaci\u00f3n referida, la Oficina de Apoyo Judicial de Paloquemao inform\u00f348 que el expediente digital ya hab\u00eda sido enviado por el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1. Por ese motivo, someti\u00f3 la impugnaci\u00f3n a reparto el 24 de mayo de 2021. Su estudio le correspondi\u00f3 al Juzgado 18 Penal del Circuito con Funci\u00f3n de Conocimiento. En tal circunstancia, solicit\u00f3 a la Corte \u201caclarar si se debe someter nuevamente a reparto la impugnaci\u00f3n de la acci\u00f3n constitucional\u201d o no.\u00a0 \u00a0<\/p>\n<p>Mediante Auto del 26 de julio de 2021, la Magistrada Sustanciadora orden\u00f3 a la Oficina de Apoyo Judicial de Paloquemao, de un lado, abstenerse de efectuar nuevamente el reparto correspondiente. Del otro, comunicar al Juzgado 18 Penal del Circuito de Conocimiento el Auto 318 de 22 de junio de 2021, proferido por la Sala Sexta de Revisi\u00f3n de esta Corporaci\u00f3n. \u00a0<\/p>\n<p>Tr\u00e1mite del recurso de apelaci\u00f3n \u00a0<\/p>\n<p>En providencia del 25 de junio de 2021, el Juzgado 18 Penal del Circuito con Funci\u00f3n de Conocimiento consider\u00f3 que hubo una indebida integraci\u00f3n del contradictorio. Lo anterior, porque no se vincularon al proceso a las entidades National Clinics Centenario S.A.S. e IPS Hospital en Casa. Entonces, declar\u00f3 la nulidad de la actuaci\u00f3n desde el auto admisorio de la demanda. Por esa raz\u00f3n, dej\u00f3 sin efecto lo actuado, salvo las pruebas recaudadas.\u00a0 \u00a0<\/p>\n<p>Tr\u00e1mite de primera instancia posterior a la nulidad declarada por el ad-quem \u00a0<\/p>\n<p>En cumplimiento de la orden del superior, mediante Auto del 29 de junio de 2021, el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 vincul\u00f3 a las entidades mencionadas. Durante el t\u00e9rmino otorgado, recibi\u00f3 la siguiente respuesta. \u00a0<\/p>\n<p>Intervenci\u00f3n de IPS Hospital en Casa \u00a0<\/p>\n<p>El 30 de junio de 2021, la IPS asegur\u00f3 que no presta el servicio de salud a la accionante desde noviembre de 2018. Asimismo, precis\u00f3 que no tiene \u00f3rdenes de servicio pendientes de cumplir con la usuaria Por lo anterior, solicit\u00f3 su desvinculaci\u00f3n del proceso, por falta de legitimaci\u00f3n por pasiva49.\u00a0 \u00a0<\/p>\n<p>Por su parte, la IPS Emmanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S. y la IPS National Clinics Centenario S.A.S., a pesar de su vinculaci\u00f3n al tr\u00e1mite ordenada por el juez de segunda instancia, no se pronunciaron respecto del asunto de la referencia50.\u00a0 \u00a0<\/p>\n<p>De igual forma, mediante oficio 279 del 29 de junio de 2021, ese despacho le corri\u00f3 traslado a la accionada de la declaratoria de nulidad proferida por el Juzgado 18 Penal del Circuito con Funci\u00f3n de Conocimiento de Bogot\u00e1, para que ejerciera su derecho a la defensa. Sin embargo, FAMISANAR EPS guard\u00f3 silencio. \u00a0<\/p>\n<p>Decisi\u00f3n de \u00fanica instancia proferida despu\u00e9s de las dos nulidades \u00a0<\/p>\n<p>Mediante sentencia del 29 de julio de 2021, el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 tutel\u00f3 los derechos fundamentales a la salud y a la vida en condiciones dignas de la accionante en su faceta de acceso al diagn\u00f3stico.\u00a0 \u00a0<\/p>\n<p>En ese sentido, orden\u00f3 a la entidad demandada valorar la condici\u00f3n m\u00e9dica actual de la actora. Se\u00f1al\u00f3 que, en ese procedimiento, se debe determinar la necesidad, viabilidad y pertinencia de prestar a la accionada los servicios de enfermer\u00eda o auxiliar de enfermer\u00eda 24 horas diarias y de transporte especial o ambulancia, as\u00ed como el suministro de pa\u00f1itos, crema antipa\u00f1alitis, crema anti-escaras, crema para piel diab\u00e9tica y silla de ruedas. La mencionada valoraci\u00f3n debe realizarla por intermedio de una de sus IPS adscritas, especialistas o junta interdisciplinaria. Adicionalmente, dispuso un t\u00e9rmino de cinco d\u00edas siguientes a la notificaci\u00f3n de la decisi\u00f3n para el cumplimiento de la orden. Lo anterior, sin oponer obst\u00e1culos para el acceso al servicio que busquen dilatar el cumplimiento de esta orden. Finalmente, no concedi\u00f3 la pretensi\u00f3n sobre el tratamiento integral. Al respecto, consider\u00f3 que el tratamiento de las patolog\u00edas de la usuaria depender\u00e1 de las prescripciones que los m\u00e9dicos emitan. En esa medida, ordenar el tratamiento integral a la paciente implicar\u00eda suponer que los procedimientos, medicamentos y salud ser\u00e1n negados. De manera que, la pretensi\u00f3n no prospera porque conllevar\u00eda a la protecci\u00f3n anticipada de una vulneraci\u00f3n o amenaza de derechos incierta51. \u00a0<\/p>\n<p>Tr\u00e1mite en sede de revisi\u00f3n una vez subsanada la nulidad \u00a0<\/p>\n<p>Decreto oficioso de pruebas en sede de revisi\u00f3n \u00a0<\/p>\n<p>Mediante Auto del 4 de octubre de 2021, la Magistrada Sustanciadora: (i) ofici\u00f3 a la agente oficiosa para que remitiera informaci\u00f3n respecto del estado de salud de su madre; (ii) indag\u00f3 sobre el cumplimiento de la orden proferida por el juez de \u00fanica instancia; y, finalmente, (iii) solicit\u00f3 a FAMISANAR EPS y a la IPS Emanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S que informaran a este despacho sobre el tratamiento que han dado a las condiciones de salud de la accionante.\u00a0 \u00a0<\/p>\n<p>Respuesta de FAMISANAR EPS \u00a0<\/p>\n<p>El 8 de octubre de 2021, FAMISANAR EPS inform\u00f3 que agend\u00f3 una junta m\u00e9dica para definir la necesidad, viabilidad y pertinencia de ordenar servicios como: enfermer\u00eda y\/o auxiliar de enfermer\u00eda 24 horas diarias, transporte especial y\/o ambulancia, pa\u00f1itos, crema antipa\u00f1alitis, cremas anti-escaras, crema para piel diab\u00e9tica y silla de ruedas. Asimismo, confirm\u00f3 que la accionante fue objeto de una nueva valoraci\u00f3n el 7 de octubre de 2021. En ella participaron el terapeuta y la jefe de zona para valorar la pertinencia de la prestaci\u00f3n de los servicios domiciliarios y la entrega de insumos a la paciente. Asegur\u00f3 que remitir\u00e1 a este despacho la historia cl\u00ednica correspondiente cuando la IPS Emanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S la env\u00ede a la EPS. Tambi\u00e9n, precis\u00f3 que la entidad ha autorizado los servicios mencionados a la agenciada. Para sustentar esa afirmaci\u00f3n manifest\u00f3 que \u201cla totalidad de servicios prestados a favor del paciente por los diagn\u00f3sticos objeto de solicitud, se encuentran descritos en la Historia Cl\u00ednica del paciente\u201d52. Sin embargo, no alleg\u00f3 ese documento. \u00a0 \u00a0<\/p>\n<p>Adicionalmente, anex\u00f3 un reporte del 7 de octubre de 2021. Este contiene el hist\u00f3rico de autorizaciones realizadas a la tutelante entre el 15 de febrero de 2012 y el 6 de octubre de 2021. Ese soporte permite advertir que la accionada ha autorizado la prestaci\u00f3n de varios servicios, as\u00ed como la entrega de diferentes insumos y medicamentos a la accionante. Puntualmente, desde el 12 de marzo de 2020, registra autorizaciones para el suministro de pa\u00f1ales, suplementos alimenticios, y ox\u00edgeno en casa, as\u00ed como la prestaci\u00f3n de los servicios de atenci\u00f3n m\u00e9dica domiciliaria, transporte para la toma de laboratorios, y, el denominado \u201cpaquete mensual integral\u201d. Estas \u00faltimas, se\u00f1alan que \u201cincluye 8 horas de E\u201d53. Otras, aumentan el n\u00famero de horas a 1254.\u00a0 \u00a0<\/p>\n<p>La Secretar\u00eda General de esta Corporaci\u00f3n comunic\u00f3 el auto de pruebas a la agente oficiosa y a la IPS Emanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S55. A pesar de lo anterior, vencido el t\u00e9rmino probatorio, no contestaron la solicitud presentada por este despacho. \u00a0<\/p>\n<p>Requerimiento y decreto oficioso de pruebas\u00a0 \u00a0<\/p>\n<p>En atenci\u00f3n a la intervenci\u00f3n de la accionada, mediante Auto del 15 de octubre de 2021, la Magistrada Sustanciadora ofici\u00f3 a FAMISANAR EPS para que: (i) allegara la historia cl\u00ednica de la agenciada, las prescripciones proferidas por los profesionales de la salud en su favor y la entrega de los medicamentos, insumos y tratamientos a partir del 21 de febrero de 2020, fecha en la que la actora present\u00f3 la acci\u00f3n de tutela; (ii) precisara cu\u00e1l fue el resultado de las valoraciones m\u00e9dicas agendadas en favor de la accionante con ocasi\u00f3n del fallo de instancia proferido el 29 de julio de 2021; (iii) aclarara qu\u00e9 actuaciones ha realizado para tratar las patolog\u00edas diagnosticadas a la paciente en las valoraciones agendadas en cumplimiento del fallo de instancia; y, (iv) explicara qu\u00e9 servicios est\u00e1n incluidos en el \u201cpaquete mensual integral\u201d. Puntualmente, qu\u00e9 significa la inclusi\u00f3n de un n\u00famero de horas \u201cE\u201d.\u00a0 \u00a0<\/p>\n<p>Adicionalmente, el despacho requiri\u00f3 a la IPS Emanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S. para que cumpliera con la orden del numeral tercero de la parte resolutiva del Auto del 4 de octubre de 202156. Asimismo, ofici\u00f3 una vez m\u00e1s a la agente oficiosa para que brindara la informaci\u00f3n relacionada con las condiciones de salud en que se encuentra la accionante.\u00a0 \u00a0<\/p>\n<p>Respuesta de FAMISANAR EPS \u00a0<\/p>\n<p>El 25 de octubre de 2021, la accionada asegur\u00f3 que no puede allegar la historia cl\u00ednica de la paciente. Se\u00f1al\u00f3 que el deber de guarda y custodia de ese documento est\u00e1 a cargo de la IPS, en virtud del art\u00edculo 13 de la Resoluci\u00f3n 1995 de 1999. Asimismo, expuso que no puede acceder a esos documentos porque, de conformidad con el art\u00edculo 24 de la Ley 1755 de 2015, tienen car\u00e1cter reservado.\u00a0 \u00a0<\/p>\n<p>En todo caso, afirm\u00f3 que, dentro del t\u00e9rmino otorgado por el despacho, la IPS correspondiente alleg\u00f3 la historia cl\u00ednica de las valoraciones realizadas a la paciente el 13 de enero de 2021. Asegur\u00f3 que, en ese documento, no hay prescripciones m\u00e9dicas de pa\u00f1itos h\u00famedos, silla de ruedas, crema anti-escaras y crema antipa\u00f1alitis.\u00a0 \u00a0<\/p>\n<p>Por \u00faltimo, asegur\u00f3 que, en un cuadro de Excel adjunto a la respuesta, explic\u00f3 en qu\u00e9 consiste el paquete mensual integral. Seg\u00fan ese documento, en los meses de febrero y marzo de 2020, ese servicio incluy\u00f3 una valoraci\u00f3n m\u00e9dica mensual, nutrici\u00f3n y terapias f\u00edsicas, respiratorias, ocupacionales y del lenguaje. A partir de abril de 2020, el servicio de enfermer\u00eda fue adicionado. Inicialmente, le prescribieron 3 horas diarias de ese servicio durante la semana57. Luego, la cantidad de horas diarias durante el mismo periodo aument\u00f3 a 8 horas58 y 12 horas59. Finalmente, en el mes de octubre de 2021, le ordenaron 24 horas diarias de la prestaci\u00f3n del servicio de domingo a domingo. Asimismo, precis\u00f3 que determinado n\u00famero de horas de \u201cE\u201d, corresponde al servicio de enfermer\u00eda.\u00a0 \u00a0<\/p>\n<p>Para soportar sus afirmaciones, remiti\u00f3 copias de las notas del servicio de enfermer\u00eda prestado entre el 1\u00b0 de enero y el 23 de octubre de 202160 y de la historia cl\u00ednica de la paciente que contiene las valoraciones m\u00e9dicas del 13 de enero al 7 de octubre de 202161. Asimismo, alleg\u00f3 dos documentos Excel. Uno de ellos, contiene el hist\u00f3rico de entrega de medicamentos a la paciente entre el 18 de febrero y el 16 de octubre de 202162. El otro contiene la descripci\u00f3n de los servicios de autorizados a la usuaria como parte del plan de manejo integral desde febrero de 2020 hasta octubre de 202163. \u00a0<\/p>\n<p>Al d\u00eda siguiente, dio alcance a su respuesta inicial. En esa oportunidad, aclar\u00f3 que, antes de la valoraci\u00f3n realizada el 7 de octubre de 2021, la usuaria no contaba con prescripciones m\u00e9dicas, ni con autorizaciones para los servicios de enfermer\u00eda y\/o auxiliar de enfermer\u00eda 24 horas diarias, transporte especial y\/o ambulancia, pa\u00f1itos h\u00famedos, crema antipa\u00f1alitis, cremas anti escaras, crema para piel diab\u00e9tica y silla de ruedas. De igual forma, expuso que tampoco existe un concepto m\u00e9dico que establezca que la paciente no requiere los insumos solicitados para su tratamiento64. \u00a0 \u00a0<\/p>\n<p>Por otra parte, advirti\u00f3 que, en la valoraci\u00f3n m\u00e9dica del 7 de octubre de 2021, el profesional de la salud orden\u00f3: (i) la prestaci\u00f3n del servicio de enfermer\u00eda domiciliaria 24 horas diarias de domingo a domingo; (ii) interconsulta de fisiatr\u00eda; (iii) terapias domiciliarias mensuales65; (iv) pa\u00f1itos h\u00famedos paquete por 100 unidades 3 paquetes por mes; (v) crema antipa\u00f1alitis nistatina 100.000 crema t\u00f3pica para uso 3 veces por d\u00eda, entregar 2 tubos por mes, 12 por 6 meses; (vi) crema anti escara marly 420gr para uso 2 veces por d\u00eda, entregar 2 frasco por mes, 12 por 6 meses; (vii) valoraci\u00f3n por neurolog\u00eda; y, (viii) transporte redondo servicio puerta a puerta en ambulancia b\u00e1sica para asistir a citas m\u00e9dicas o toma de estudios cuando lo requiera, 4 traslados redondos por mes, 24 por 6 meses. Respecto de este \u00faltimo, afirm\u00f3 que el \u00e1rea encargada del servicio de transporte ambulatorio inform\u00f3 a la agente oficiosa el procedimiento para agendarlo66. \u00a0<\/p>\n<p>Adicionalmente, se\u00f1al\u00f3 que la profesional de la salud encargada no prescribi\u00f3 la silla de ruedas. Por esa raz\u00f3n, agend\u00f3 cita m\u00e9dica en la IPS ortop\u00e9dicos Chapinero, para el viernes 5 de noviembre a las 11:30 a.m., para determinar la pertinencia de prescribir este insumo67. \u00a0<\/p>\n<p>Como sustento de sus afirmaciones, alleg\u00f3 nuevamente los documentos anexos al escrito anterior. Adicionalmente, remiti\u00f3 la historia cl\u00ednica de las atenciones domiciliarias a la paciente durante el 202068 y de las valoraciones realizadas por la IPS Cafam desde el 2010 hasta el 202069.\u00a0 \u00a0<\/p>\n<p>Respuesta de la agente oficiosa \u00a0<\/p>\n<p>El 4 de noviembre de 2021, mediante correo electr\u00f3nico, la agente asegur\u00f3 que su madre cuenta con el servicio de enfermer\u00eda 24 horas diarias. Sin embargo, precis\u00f3 que la EPS no le ha autorizado el suministro de los dem\u00e1s insumos m\u00e9dicos prescritos en la valoraci\u00f3n m\u00e9dica del 7 de octubre de 2021. Al respecto, manifest\u00f3 que asisti\u00f3 a la droguer\u00eda de CAFAM para reclamar los elementos de salud correspondientes. En ese lugar, le informaron que deb\u00eda contar con una autorizaci\u00f3n de FAMISANAR EPS.\u00a0 \u00a0<\/p>\n<p>Entonces, acudi\u00f3 a las oficinas de esa entidad ubicadas en Soacha, con el fin de obtener la aludida autorizaci\u00f3n. Afirm\u00f3 que le present\u00f3 a los funcionarios de la EPS las f\u00f3rmulas m\u00e9dicas y el fallo de tutela del juez de instancia. En todo caso, le negaron tanto la autorizaci\u00f3n como el suministro de los insumos prescritos por los m\u00e9dicos tratantes. Tambi\u00e9n, asegur\u00f3 que se han presentado demoras en la entrega de algunos medicamentos. Puntualmente, acetilcestina granulado X 600 gr y parche de rivastatinina. \u00a0<\/p>\n<p>La Secretar\u00eda General de esta Corporaci\u00f3n comunic\u00f3 el auto de pruebas a la IPS Emanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S70. A pesar de lo anterior, vencido el t\u00e9rmino probatorio, no contest\u00f3 la solicitud presentada por este despacho. \u00a0<\/p>\n<p>II. CONSIDERACIONES \u00a0<\/p>\n<p>Competencia\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Corresponde a la Sala Sexta de Revisi\u00f3n de la Corte Constitucional revisar la decisi\u00f3n de \u00fanica instancia proferida por el Juzgado Veintitr\u00e9s Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 de conformidad con lo dispuesto en los art\u00edculos 86 y 241.9 de la Constituci\u00f3n y, 31 a 36 del Decreto 2591 de 1991. \u00a0 \u00a0<\/p>\n<p>Asunto objeto de an\u00e1lisis y problemas jur\u00eddicos \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En esta oportunidad, la Sala estudia la acci\u00f3n de tutela promovida en nombre de una persona de la tercera edad, quien padece enfermedades cr\u00f3nicas que restringen su movilidad y autonom\u00eda para desempe\u00f1ar las actividades b\u00e1sicas del diario vivir, como son comer o desplazarse, entre otras71. Seg\u00fan la agente oficiosa, el tratamiento de las enfermedades de la agenciada requiere de la prestaci\u00f3n de los servicios de enfermer\u00eda o auxiliar de enfermer\u00eda 24 horas diarias y, de transporte especial o ambulancia, as\u00ed como el suministro de silla de ruedas, pa\u00f1itos h\u00famedos, crema antipa\u00f1alitis, crema anti-escaras y crema para piel diab\u00e9tica. En todo caso, a su juicio, los m\u00e9dicos tratantes no han prescrito los insumos y servicios mencionados, como consecuencia de las pol\u00edticas implementadas por la EPS accionada. Por esa raz\u00f3n, invoc\u00f3 la protecci\u00f3n de los derechos de su madre a la vida en condiciones dignas, a la salud y a la vida72. En consecuencia, solicit\u00f3 ordenar a la EPS autorizar el suministro de los servicios e insumos mencionados. Asimismo, pidi\u00f3 que se conceda la prestaci\u00f3n de un tratamiento integral para las patolog\u00edas de la agenciada.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00bfLa EPS accionada vulner\u00f3 los derechos fundamentales a la salud y a la vida digna de la agenciada, al negarse a autorizar la prestaci\u00f3n de los servicios de enfermer\u00eda o auxiliar de enfermer\u00eda 24 horas diarias y de transporte especial o ambulancia, el suministro de silla de ruedas, pa\u00f1itos h\u00famedos, crema antipa\u00f1alitis, crema anti-escaras y crema para piel diab\u00e9tica, y el tratamiento integral de las patolog\u00edas de la accionante, con fundamento en que esos elementos no fueron prescritos por los m\u00e9dicos tratantes?\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Con el prop\u00f3sito de resolver este interrogante, la Sala: (i) expondr\u00e1 el fundamento constitucional del derecho a la salud de las personas de la tercera edad; (ii) explicar\u00e1 la figura del tratamiento integral; (iii) har\u00e1 referencia al derecho al diagn\u00f3stico, (iv) reiterar\u00e1 las reglas jurisprudenciales sobre el suministro de los servicios de enfermer\u00eda o auxiliar de enfermer\u00eda y de transporte interurbano, as\u00ed como de silla de ruedas, pa\u00f1itos h\u00famedos, crema anti-escaras y antipa\u00f1alitis; y, finalmente, (v) decidir\u00e1 el caso concreto. \u00a0 \u00a0<\/p>\n<p>Procedencia de la acci\u00f3n de tutela73 \u00a0<\/p>\n<p>Legitimaci\u00f3n por activa\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El art\u00edculo 86 de la Constituci\u00f3n establece que cualquier persona puede interponer la acci\u00f3n de tutela \u201cpor s\u00ed misma o por quien act\u00fae en su nombre\u201d. En desarrollo de lo anterior, el art\u00edculo 10 del Decreto 2591 de 199174 define los titulares de la acci\u00f3n. En concreto, consagra que podr\u00e1 ser interpuesta: (i) directamente por el interesado; (ii) por intermedio de un representante legal; caso de los menores de edad y las personas jur\u00eddicas; (iii) mediante apoderado judicial; (iv) por medio de un agente oficioso; o, (v) a trav\u00e9s de la Defensor\u00eda del Pueblo o del personero municipal75. En el caso objeto de estudio, la solicitud de amparo fue presentada por un agente oficioso. Por lo tanto, la Sala debe establecer si cumple con los requisitos establecidos para aplicar esa figura procesal.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La agencia oficiosa le permite a una persona interponer acci\u00f3n de tutela para defender los derechos de otra. Esta figura procede siempre que el agenciado no est\u00e9 en condiciones de ejercer su propia defensa76. La jurisprudencia constitucional ha se\u00f1alado que esta figura es una expresi\u00f3n del principio de solidaridad porque busca impedir que la falta de capacidad de las personas para defenderse sea un obst\u00e1culo para la protecci\u00f3n de sus derechos fundamentales. En concreto, cuando se trata de sujetos de especial protecci\u00f3n constitucional y que no pueden agenciar por s\u00ed mismos la garant\u00eda de sus derechos.\u00a0 \u00a0 \u00a0<\/p>\n<p>En ese sentido, este Tribunal ha considerado que para aplicar este mecanismo: (i) el agente oficioso debe manifestar que act\u00faa en defensa de los derechos de un tercero; y, (ii) de las pruebas aportadas o de las circunstancias se\u00f1aladas en la acci\u00f3n de tutela, debe extraerse que el titular de los derechos est\u00e1 en una situaci\u00f3n de desamparo o de debilidad que le impide actuar directamente77. De igual forma, ha se\u00f1alado que no es necesario que exista una relaci\u00f3n formal entre el agente y el titular de los derechos, ni una delegaci\u00f3n expresa78.\u00a0 \u00a0<\/p>\n<p>En cuanto a la ratificaci\u00f3n posterior de la acci\u00f3n, esta Corporaci\u00f3n afirm\u00f3 que, \u201cuna de las principales diferencias de [la agencia oficiosa] en el r\u00e9gimen procesal de la acci\u00f3n de tutela frente a lo que ocurre en la generalidad de los procesos judiciales, es que no se exige que la persona agenciada ratifique el amparo constitucional ante el juez de la causa, lo que se explica por la informalidad que rige este tr\u00e1mite y por la circunstancia de que la protecci\u00f3n que se busca debe operar de forma preferente y sumaria\u201d79. En todo caso, cuando el titular de los derechos ratifica la actuaci\u00f3n del agente oficioso, convalida la actuaci\u00f3n. Por lo tanto, le otorga legitimidad en la causa por activa80.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para la Sala, este caso re\u00fane los requisitos descritos con anterioridad. En primer lugar, la agente manifest\u00f3 que interpuso la acci\u00f3n de tutela para proteger los derechos fundamentales de su madre. Por otra parte, la agenciada no est\u00e1 en capacidad de defender sus derechos por s\u00ed misma. Lo anterior, porque, debido a su avanzada edad y a su estado de salud, \u201cdepende por completo de un tercero para desarrollar sus actividades diarias como ba\u00f1arse, alimentarse y vestirse\u201d81. De manera que no puede acceder directamente a la administraci\u00f3n de justicia. Y, finalmente, en este caso no es necesaria la ratificaci\u00f3n posterior por parte de la agenciada porque, como se advirti\u00f3 previamente, no puede actuar directamente. Adem\u00e1s, el referido requisito, en estas circunstancias, resulta manifiestamente desproporcionado en atenci\u00f3n a la condici\u00f3n m\u00e9dica de la agenciada, a su avanzada edad y a sus limitaciones f\u00edsicas. En consecuencia, la solicitud de amparo cumple con el requisito de legitimidad en la causa por activa. \u00a0 \u00a0<\/p>\n<p>Legitimaci\u00f3n por pasiva \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Las acciones de tutela pueden dirigirse en contra de autoridades y particulares. Lo anterior, siempre que tengan capacidad legal para ser llamados a responder por la presunta vulneraci\u00f3n o amenaza de los derechos invocados82. Seg\u00fan el art\u00edculo 42.2 del Decreto 2591 de 199183, en materia de salud, la solicitud de amparo procede en contra de personas de derecho privado encargadas de la prestaci\u00f3n del servicio p\u00fablico de salud84. En este caso, la demanda est\u00e1 dirigida contra FAMISANAR EPS. De igual manera, a este proceso fueron vinculadas las sociedades IPS Emmanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S., National Clinics Centenario S.A.S. e IPS Hospital en Casa. Esas entidades privadas est\u00e1n dedicadas a la prestaci\u00f3n de servicios de salud, puntualmente, a quienes, como la agenciada, tienen la calidad de afiliados a la EPS accionada. Igualmente, las IPS vinculadas, en diferentes \u00e9pocas, han estado encargadas de la prestaci\u00f3n de los servicios de salud a la agenciada.\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para la Sala, esas autoridades tienen la capacidad legal para ser llamadas a responder por la presunta vulneraci\u00f3n o amenaza de los derechos invocados, porque en ejercicio de sus funciones han prestado el servicio de salud a la agenciada. De manera que el recurso de amparo satisface este requisito. \u00a0 \u00a0<\/p>\n<p>Inmediatez\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De conformidad con el art\u00edculo 86 superior85, las personas pueden interponer acci\u00f3n de tutela en todo tiempo y lugar. Al respecto, esta Corporaci\u00f3n ha sostenido que, si bien no existe un t\u00e9rmino de caducidad en tutela, lo cierto es que debe interponerse en un tiempo razonable. De otro modo, quedar\u00eda desnaturalizada la funci\u00f3n de protecci\u00f3n urgente de derechos atribuida a este mecanismo judicial86.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La agente oficiosa solicit\u00f3 directamente a FAMISANAR EPS, el 13 de noviembre de 2019, la prestaci\u00f3n del servicio de enfermer\u00eda 24 horas para su madre87. La entidad neg\u00f3 la petici\u00f3n el 4 de diciembre siguiente88. En atenci\u00f3n a la situaci\u00f3n de su madre, la agente insisti\u00f3 el 25 de enero de 2020 en su solicitud. En todo caso, su petici\u00f3n no fue atendida89. Seg\u00fan el escrito de tutela, por la falta de prestaci\u00f3n del servicio requerido, la agenciada sufri\u00f3 una ca\u00edda el 26 de enero de 2020, lo que agrav\u00f3 su situaci\u00f3n90. Por esa raz\u00f3n, el 26 de febrero de 2020, la agente oficiosa present\u00f3 la solicitud de amparo. Eso significa que, la agenciada interpuso la acci\u00f3n de tutela un mes despu\u00e9s de haber insistido en la provisi\u00f3n de los insumos y no haber obtenido respuesta a su petici\u00f3n. Aquel, coincide con el momento en que las condiciones de salud de la agenciada se agravaron con ocasi\u00f3n del accidente. Por lo tanto, la Sala considera que el amparo fue presentado dentro de un t\u00e9rmino razonable. De esta manera el requisito est\u00e1 acreditado.\u00a0 \u00a0 \u00a0<\/p>\n<p>Subsidiariedad\u00a0 \u00a0<\/p>\n<p>1. En virtud del principio de subsidiariedad, la tutela proceder\u00e1 como mecanismo principal (art\u00edculo 86 C.P.91), cuando el afectado no disponga de otro medio de defensa judicial id\u00f3neo y eficaz para proteger sus derechos92. En cada caso concreto, el juez constitucional deber\u00e1 verificar, de un lado, la existencia de un mecanismo judicial para garantizar los derechos del accionante. Y, del otro, la idoneidad y eficacia de aquel para restablecer de forma oportuna, efectiva e integral los derechos invocados93. Este an\u00e1lisis debe ser sustancial y no simplemente formal94. De igual manera, ante la existencia de medios judiciales id\u00f3neos y eficaces, el amparo proceder\u00e1 transitoriamente para evitar un perjuicio irremediable95.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Adicionalmente, esta Corporaci\u00f3n ha reconocido que, si el actor es un sujeto de especial protecci\u00f3n constitucional, el juez de tutela debe aplicar criterios de an\u00e1lisis m\u00e1s amplios, aunque no menos rigurosos96. En efecto, la jurisprudencia ha sostenido que, en los casos de ni\u00f1os, ni\u00f1as y adolescentes, personas cabeza de familia, en situaci\u00f3n de discapacidad, de la tercera edad o poblaci\u00f3n desplazada, entre otros, se debe brindar un tratamiento diferenciado97.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para el caso objeto de estudio, en principio, existe un mecanismo ordinario de defensa judicial al que la demandante podr\u00eda acudir. En efecto, el Legislador atribuy\u00f3 competencias jurisdiccionales a la Superintendencia Nacional de Salud (en adelante SNS) para conocer de varias controversias98. Entre ellas, las relacionadas con la cobertura de servicios, tecnolog\u00edas o procedimientos de salud incluidos99 en el PBS100. Lo anterior, siempre que su negativa ponga en riesgo o amenace la salud del usuario.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. A pesar de lo anterior, esta Corporaci\u00f3n ha reconocido que el medio judicial descrito no es id\u00f3neo, ni eficaz. En primer lugar, porque la SNS afronta un d\u00e9ficit estructural. De conformidad con los hallazgos de la audiencia del 16 de diciembre de 2018, celebrada en el marco de la Sala Especial de Seguimiento a la Sentencia T-760 de 2008101, esa entidad carece de las herramientas institucionales para decidir los casos dentro del t\u00e9rmino legal102. Esta situaci\u00f3n gener\u00f3 un atraso de entre dos y tres a\u00f1os para solucionar las controversias de fondo103. As\u00ed, esta Corte precis\u00f3 que, mientras dichas condiciones persistan, este medio judicial no resultar\u00e1 id\u00f3neo, ni eficaz104. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Posteriormente, el Legislador profiri\u00f3 la Ley 1949 de 2019 con el fin, entre otros, de fortalecer la capacidad de la SNS en materia sancionatoria105. En ese sentido: (i) ampli\u00f3 los t\u00e9rminos que tiene la entidad para adoptar una decisi\u00f3n de fondo, (ii) determin\u00f3 que la Sala Laboral del Tribunal Superior del Distrito Judicial del domicilio del apelante conocer\u00e1 en segunda instancia de estos casos; (iii) regul\u00f3 las medidas cautelares que se pueden imponer; entre otros asuntos. Sin embargo, en la Sentencia SU-508 de 2020106, la Sala Plena se\u00f1al\u00f3 que las dificultades administrativas contin\u00faan107 porque a\u00fan no se cuenta con informaci\u00f3n que permita concluir de forma objetiva que la situaci\u00f3n fue superada108. De manera que, dicho mecanismo jurisdiccional carece de idoneidad y eficacia.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Adicionalmente, la Corte Constitucional ha advertido algunas condiciones normativas que afectan la idoneidad y eficacia del medio judicial. Al respecto, se\u00f1al\u00f3 que el procedimiento no establece: (i) el t\u00e9rmino para proferir la decisi\u00f3n de segunda instancia109; (ii) el efecto de la impugnaci\u00f3n110; (iii) las garant\u00edas para el cumplimiento de la decisi\u00f3n111; (iv) qu\u00e9 sucede cuando la EPS no responde o lo hace parcialmente112; (v) ni el procedimiento de la agencia oficiosa en estos casos113. Estos asuntos normativos pueden extender el t\u00e9rmino de duraci\u00f3n del procedimiento ante la SNS o incluso impedir el acceso a la administraci\u00f3n de justicia, en algunos casos114. En ese sentido, el medio de defensa aludido no es id\u00f3neo, ni eficaz para garantizar los derechos de los usuarios del sistema de salud.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el caso objeto de estudio, la agente oficiosa pretende la protecci\u00f3n del derecho a la salud de su madre, quien es una persona de la tercera edad y en dif\u00edciles condiciones de salud115. Esta Sala considera que el medio judicial de defensa ante la SNS no resulta id\u00f3neo, ni eficaz para proteger los derechos de la agenciada. Lo anterior, porque existe un d\u00e9ficit estructural y varios vac\u00edos normativos que impiden una correcta administraci\u00f3n de justicia en su caso y la situaci\u00f3n de salud de la accionante no da espera.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por otra parte, en casos de personas de la tercera edad y con grav\u00edsimas afectaciones a su salud, la Corte ha tenido en cuenta tal situaci\u00f3n como un criterio para evaluar la eficacia de los medios ordinarios de defensa judicial. Al respecto, ha se\u00f1alado que exigirles a estos sujetos acudir al mecanismo principal de defensa implicar\u00eda someterlos a una espera irrazonable y desproporcionada. Lo anterior, porque \u201ccuando una persona sobrepasa el promedio de vida de los colombianos (\u2026) por su avanzada edad [es dable suponer que], ya su existencia se habr\u00eda extinguido para la fecha de una decisi\u00f3n dentro de un proceso judicial ordinario\u201d116. En esta oportunidad, la agenciada tiene 86 a\u00f1os. Es decir, supera el promedio de expectativa de vida de los colombianos117. Adem\u00e1s, est\u00e1 diagnosticada con graves padecimientos. Por lo tanto, resulta desproporcionado exigirle que acuda al tr\u00e1mite judicial ante la SNS118, con mayor raz\u00f3n si se ha demostrado la falta de idoneidad general de ese mecanismo judicial de defensa. En consecuencia, la acci\u00f3n de tutela es el medio eficaz para garantizar el derecho a la salud de la agenciada y procede como mecanismo definitivo de protecci\u00f3n. As\u00ed, esta Sala encuentra satisfecho el requisito de subsidiariedad. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Acreditada la procedencia de la acci\u00f3n de tutela en el presente asunto, la Sala analizar\u00e1 los temas de fondo que permitir\u00e1n responder al problema jur\u00eddico que orienta esta providencia.\u00a0 \u00a0 \u00a0<\/p>\n<p>El derecho a la salud de las personas de la tercera edad. Reiteraci\u00f3n de jurisprudencia119 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El art\u00edculo 49 de la Constituci\u00f3n Pol\u00edtica consagra la salud como un servicio p\u00fablico en cabeza del Estado. En ese sentido, le corresponde organizar, dirigir y reglamentar la prestaci\u00f3n de servicios de salud a todas las personas120. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En desarrollo de esos preceptos constitucionales, esta Corporaci\u00f3n ha sostenido que la salud tiene una doble connotaci\u00f3n: (i) derecho fundamental121; y, (ii) servicio p\u00fablico esencial obligatorio122. Respecto a la primera faceta, ha precisado que debe prestarse de manera oportuna, eficiente y con calidad. Asimismo, debe atender a los principios de continuidad, integralidad e igualdad. En cuanto a la segunda, la salud debe atender a los principios de eficiencia, universalidad y solidaridad, de conformidad con los art\u00edculos 48 y 49 superiores123. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Tanto la normativa124 como la jurisprudencia actual125 disponen que la salud es un derecho fundamental aut\u00f3nomo e irrenunciable. Entre otros elementos, comprende el acceso a los servicios de salud de manera completa, oportuna, eficaz y con calidad. En ese sentido, el art\u00edculo 8\u00ba de la Ley 1751 de 2015 consagr\u00f3 el principio de la integralidad126. Esta Corporaci\u00f3n ha definido ese principio como el derecho de los usuarios del sistema a recibir la atenci\u00f3n y el tratamiento completo de sus enfermedades, de conformidad con lo prescrito por el m\u00e9dico tratante127.\u00a0 \u00a0 \u00a0<\/p>\n<p>Asimismo, la Sentencia C-313 de 2014128 estableci\u00f3 que, en virtud de la integralidad, el Estado y las entidades encargadas de la prestaci\u00f3n del servicio deben adoptar todas las medidas necesarias para brindar un tratamiento que efectivamente mejore las condiciones de salud y calidad de vida de las personas. De manera que, cuando es imposible la recuperaci\u00f3n de la salud, se deben proveer los servicios y tecnolog\u00edas necesarios para sobrellevar la enfermedad. Lo anterior, para garantizar al paciente una vida en condiciones dignas129. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ahora bien, en la Sentencia SU-508 de 2020130, la Sala Plena advirti\u00f3 que el car\u00e1cter universal del derecho a la salud no obsta para que se adopten medidas de protecci\u00f3n afirmativas en favor de los sujetos de especial protecci\u00f3n constitucional, como lo son las personas de la tercera edad131. Al respecto, la jurisprudencia de este Tribunal ha se\u00f1alado que este grupo afronta debilidades para desarrollar ciertas funciones y actividades. Como consecuencia de ello, estas personas resultan inmersas en situaciones de exclusi\u00f3n en el \u00e1mbito econ\u00f3mico, social y cultural. De manera que, es necesario adoptar medidas que permitan suprimir esas barreras para garantizar la igualdad material de esa poblaci\u00f3n132. \u00a0 \u00a0<\/p>\n<p>En esa providencia, este Tribunal precis\u00f3 que los derechos fundamentales de las personas de la tercera edad deben interpretarse de conformidad con el principio de dignidad humana133 y con la Observaci\u00f3n General No. 14 proferida por el Comit\u00e9 de Derechos Econ\u00f3micos, Sociales y Culturales &#8211; DESC134. Este documento orienta la interpretaci\u00f3n del derecho a la salud de personas en situaci\u00f3n de vulnerabilidad. Asimismo, consider\u00f3 que la protecci\u00f3n de sus derechos es prevalente135, es decir, tiene una relevancia trascendental136. Por lo tanto, las instituciones encargadas de prestar servicios de salud deben adoptar mecanismos para garantizar a este grupo poblacional la prestaci\u00f3n de los servicios de salud que requieran137.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En ese mismo sentido, la Sentencia T-221 de 2021138 se\u00f1al\u00f3 que los servicios de salud que requieran las personas de la tercera edad deben garantizarse de manera continua, permanente, oportuna y eficiente. Lo anterior, en atenci\u00f3n, entre otras cosas, al deber de protecci\u00f3n y asistencia de este grupo poblacional139, consagrado en el art\u00edculo 46 de la Constituci\u00f3n140.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por su parte, en el art\u00edculo 11 de la Ley Estatutaria de Salud, el Legislador estableci\u00f3 que, la atenci\u00f3n en salud de las personas de la tercera edad gozar\u00e1 de especial protecci\u00f3n del Estado. En ese sentido, no ser\u00e1 limitada por asuntos econ\u00f3micos, ni administrativos. Adicionalmente, dispone que las instituciones del sector salud deber\u00e1n definir procesos de atenci\u00f3n intersectoriales e interdisciplinarios para garantizarles las mejores condiciones de atenci\u00f3n141.\u00a0 \u00a0 \u00a0<\/p>\n<p>Tratamiento integral\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La jurisprudencia constitucional ha diferenciado el principio de integralidad del tratamiento integral. Respecto del primero, se\u00f1al\u00f3 que es un mandato que debe guiar las actuaciones de las entidades prestadores del servicio de salud. En cuanto al segundo, expuso que es una orden que puede proferir el juez de tutela. Su cumplimiento supone una atenci\u00f3n \u201cininterrumpida, completa, diligente, oportuna y con calidad del usuario\u201d142. De manera que, en esos casos, la prestaci\u00f3n del servicio de salud debe incluir todos los elementos que prescriba el m\u00e9dico tratante143.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para ordenar el tratamiento integral, el juez de tutela debe verificar que: (i) la EPS fue negligente en el cumplimiento de sus deberes; (ii) existen prescripciones m\u00e9dicas que especifiquen tanto el diagn\u00f3stico del paciente, como los servicios o insumos que requiere; y, (iii) el demandante es sujeto de especial protecci\u00f3n constitucional o est\u00e1 en condiciones extremadamente precarias de salud144. En estos casos, el tratamiento del paciente debe estar claro, en tanto que la autoridad judicial no puede pronunciarse respecto de asuntos futuros e inciertos ni presumir la mala fe de la EPS145. \u00a0 \u00a0<\/p>\n<p>Derecho al diagn\u00f3stico. Reiteraci\u00f3n de jurisprudencia146 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Seg\u00fan la jurisprudencia, el derecho al diagn\u00f3stico es la facultad que tienen los usuarios de exigir una valoraci\u00f3n t\u00e9cnica, cient\u00edfica y oportuna de su estado de salud147. Ese procedimiento permite: (i) establecer las patolog\u00edas que padece el paciente; (ii) determinar el tratamiento adecuado para ellas148; e, (iii) iniciar los procedimientos correspondientes de manera oportuna149.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Asimismo, esta Corporaci\u00f3n ha reconocido que el diagn\u00f3stico es un componente fundamental del derecho a la salud150. Aquel est\u00e1 relacionado con la autodeterminaci\u00f3n de los pacientes151. En ese sentido, tiene un v\u00ednculo inescindible con la informaci\u00f3n vital que el titular del derecho a la salud debe conocer como: \u201c(i) la fuente de su patolog\u00eda, (ii) el tratamiento y (iii) las repercusiones que podr\u00eda tener en su cuerpo\u201d152. De igual forma, tambi\u00e9n tiene conexidad con la adopci\u00f3n libre de medidas en contra de la patolog\u00eda padecida153. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para la Corte, dicha garant\u00eda consta de tres dimensiones: la identificaci\u00f3n, la valoraci\u00f3n y la prescripci\u00f3n. La primera de ellas corresponde a la pr\u00e1ctica de los ex\u00e1menes que ordena el m\u00e9dico con fundamento en los s\u00edntomas del paciente. La siguiente, refiere a la valoraci\u00f3n de los resultados de dichos ex\u00e1menes por parte de los especialistas. Y, la \u00faltima, a la emisi\u00f3n de las \u00f3rdenes m\u00e9dicas pertinentes y adecuadas para tratar su estado de salud. Eso significa que el derecho al diagn\u00f3stico solo se garantiza con la prescripci\u00f3n de los elementos de salud requeridos para tratar al paciente154.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Sala Plena ha considerado que esta garant\u00eda debe protegerse en los casos en los que resulte aplicable. Esto es, cuando el encargado de prestar el derecho a la salud del paciente no realice \u201clas actividades, procedimientos e intervenciones tendientes a demostrar la presencia de la enfermedad, su estado de evoluci\u00f3n, sus complicaciones y consecuencias presentes y futuras para el paciente. Incluso, tal amparo debe otorgarse indistintamente de la urgencia de su pr\u00e1ctica, es decir, no simplemente frente al riesgo inminente que pueda sufrir la vida del paciente, sino adem\u00e1s frente a patolog\u00edas que no la comprometan directamente\u201d155.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En suma, el derecho al diagn\u00f3stico implica una valoraci\u00f3n t\u00e9cnica, cient\u00edfica y oportuna del estado de salud del paciente. Esta garant\u00eda solo se satisface con la prescripci\u00f3n de los elementos requeridos para tratar las patolog\u00edas del paciente. Adicionalmente, tiene una relaci\u00f3n estrecha con la autodeterminaci\u00f3n de los usuarios del sistema de salud. Por lo tanto, su protecci\u00f3n incluye el deber de informar a los usuarios el origen de sus patolog\u00edas, el tratamiento y los efectos de esos procedimientos en su cuerpo.\u00a0 \u00a0 \u00a0<\/p>\n<p>Reglas sobre el suministro en sede de tutela de insumos y servicios incluidos y excluidos del PBS sin prescripci\u00f3n m\u00e9dica. Reiteraci\u00f3n de jurisprudencia.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. El derecho a la salud comprende el acceso a los servicios de salud de manera completa, oportuna, eficaz y con calidad. Con la expedici\u00f3n de la Ley 1751 de 2015, el Legislador adopt\u00f3 un sistema de salud de exclusiones expl\u00edcitas, el cual se materializ\u00f3 a trav\u00e9s del PBS156. Eso significa que todos los servicios de salud est\u00e1n cubiertos por el sistema, a menos que est\u00e9n taxativamente excluidos157. La jurisprudencia ha reconocido que, el acceso a los servicios y tecnolog\u00edas de salud cubiertos por el PBS hace parte del \u00e1mbito inamovible del derecho a la salud158. Asimismo, ha se\u00f1alado que las exclusiones constituyen una restricci\u00f3n constitucional del derecho a la salud, porque garantizan la sostenibilidad del sistema. Es decir, permiten que haya una destinaci\u00f3n de los recursos del sistema de salud a la satisfacci\u00f3n de los asuntos prioritarios. Esto sin desconocer: (i) el n\u00facleo esencial del derecho a la salud; (ii) la obligaci\u00f3n de garantizar el nivel m\u00e1s alto posible de atenci\u00f3n integral en salud; y, (iii) el deber de prever una ampliaci\u00f3n progresiva en materia de prestaci\u00f3n de los servicios y tecnolog\u00edas en salud159.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Con todo, en algunas oportunidades, el acceso a insumos o servicios excluidos del PBS puede resultar necesario para garantizar el derecho a la salud o a la vida digna de las personas. Tal es el caso del suministro de pa\u00f1itos h\u00famedos en pacientes con capacidad limitada para realizar sus necesidades fisiol\u00f3gicas aut\u00f3nomamente. As\u00ed lo reconoci\u00f3 la Sala Plena en la Sentencia SU-508 de 2020160. En esa oportunidad, esta Corporaci\u00f3n consider\u00f3 que dejar de emplear algunos insumos, como los pa\u00f1itos h\u00famedos y la crema anti-escaras, en esos usuarios, puede causar dermatitis asociada a la incontinencia (DAI), lesiones de la piel con p\u00e9rdida progresiva de la misma (que generan un fuerte dolor), infecciones urinarias y lesiones cr\u00f3nicas que conducen a infecciones cut\u00e1neas. Respecto de estas \u00faltimas, precis\u00f3 que su falta de atenci\u00f3n oportuna y adecuada, en casos extremos, puede llevar a la sepsis, e incluso a la muerte161. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La jurisprudencia ha reconocido que, en principio, los pacientes deben contar con una prescripci\u00f3n m\u00e9dica para acceder a los insumos, servicios y tecnolog\u00edas de salud. En todo caso, si no cuentan con ella, el juez de tutela podr\u00e1 ordenar el suministro de esos elementos o amparar el derecho a la salud en su faceta de derecho al diagn\u00f3stico. Para el efecto, deber\u00e1 tener en cuenta las siguientes consideraciones.\u00a0 \u00a0 \u00a0<\/p>\n<p>Suministro de servicios e insumos incluidos en el PBS sin prescripci\u00f3n m\u00e9dica \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Seg\u00fan este Tribunal, es posible que los pacientes soliciten el suministro de servicios e insumos incluidos en el PBS, sin contar con la orden m\u00e9dica correspondiente. En esos casos, el juez deber\u00e1, en principio, tener en cuenta las siguientes reglas: \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>i. Si las pruebas recaudadas le permiten concluir que es evidentemente necesario para el tratamiento del paciente, podr\u00e1 disponer la entrega de lo solicitado. En este caso, la orden estar\u00e1 supeditada a la posterior ratificaci\u00f3n del profesional de la salud correspondiente.\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>i. En caso de duda sobre la necesidad de proveer lo solicitado, deber\u00e1 analizar si existe un indicio razonable sobre la afectaci\u00f3n del derecho a la salud del accionante. En ese evento, ordenar\u00e1 a la EPS respectiva que, a trav\u00e9s de sus m\u00e9dicos adscritos, determine si el paciente requiere o no el insumo o servicio pedido. Lo anterior, a fin de que lo provea162.\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La jurisprudencia ha aplicado esta regla al suministro de algunos insumos y servicios. Tambi\u00e9n, ha establecido algunas precisiones respecto de la provisi\u00f3n de servicios como el de transporte y enfermer\u00eda. A continuaci\u00f3n, la Sala reiterar\u00e1 las reglas jurisprudenciales sobre el suministro, en sede de tutela, de sillas de ruedas, crema anti- escaras, crema antipa\u00f1alitis, del servicio de transporte y del servicio enfermer\u00eda, sin contar con prescripci\u00f3n m\u00e9dica.\u00a0 \u00a0 \u00a0<\/p>\n<p>Sillas de ruedas de impulso manual163\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Seg\u00fan la jurisprudencia, las sillas de ruedas \u201cson consideradas como una ayuda t\u00e9cnica, es decir, como aquella tecnolog\u00eda que permite complementar o mejorar la capacidad fisiol\u00f3gica o f\u00edsica de un sistema u \u00f3rgano afectado\u201d164. Puntualmente, permiten el traslado adecuado de pacientes que tienen problemas de movilidad165. Esta Corporaci\u00f3n ha considerado que esos instrumentos permiten que la persona tenga una existencia m\u00e1s digna, porque reducen los efectos de la limitaci\u00f3n de movilidad que afronta el paciente166. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Las sillas de ruedas no hacen parte del listado de exclusiones del PBS establecido en la Resoluci\u00f3n 244 de 2019167. Por esa raz\u00f3n, este Tribunal ha se\u00f1alado que est\u00e1n incluidas en el PBS168. Sin embargo, no pueden ser financiadas con cargo a las UPC169. De manera que, esas entidades podr\u00e1n adelantar el procedimiento establecido en la Resoluci\u00f3n 1885 de 2018170, para solicitar el pago del costo de la ayuda t\u00e9cnica. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Seg\u00fan la Sentencia SU-508 de 2020171, cuando el paciente no cuenta con una prescripci\u00f3n m\u00e9dica y acude a la acci\u00f3n de tutela para el suministro de este insumo, el juez deber\u00e1 valorar las pruebas allegadas al proceso. Si advierte que la silla de ruedas es necesaria para el paciente, podr\u00e1 ordenar su entrega. Esa decisi\u00f3n estar\u00e1 supeditada a la posterior ratificaci\u00f3n del profesional de la salud correspondiente. En caso contrario, la autoridad judicial podr\u00e1 amparar el derecho a la salud en su faceta de diagn\u00f3stico, siempre que encuentre un indicio razonable sobre la afectaci\u00f3n del derecho a la salud que haga imperioso impartir una orden de protecci\u00f3n. En esos eventos, podr\u00e1 ordenar a la EPS que determine la necesidad del insumo por parte del usuario a trav\u00e9s de una valoraci\u00f3n m\u00e9dica. \u00a0 \u00a0<\/p>\n<p>Cremas anti-escaras \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Sala Plena ha considerado que la crema anti-escaras es una mezcla emulsionada de agua y aceite utilizadas para prevenir las \u00falceras por presi\u00f3n172. En su criterio, este insumo est\u00e1 incluido en el PBS. Al respecto, precis\u00f3 que este elemento no est\u00e1 expresamente consagrado en la lista de exclusiones establecida en la Resoluci\u00f3n 244 de 2019. Por lo tanto, hace parte del modelo de inclusi\u00f3n impl\u00edcita establecido en la normativa vigente173.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por otra parte, la Sentencia SU-508 de 2020174 asegur\u00f3 que las cremas anti-escaras no son asimilables a la emulsi\u00f3n hidratante corporal175, ni a la loci\u00f3n hidratante corporal176, las cuales est\u00e1n expresamente excluidas del PBS177. Lo anterior, porque, de un lado, ese insumo tiene una composici\u00f3n diferente de las emulsiones y de las lociones178. Y, de otro, equipararlas desconocer\u00eda lo establecido en la Sentencia C-313 de 2014179. Seg\u00fan esa decisi\u00f3n, solo est\u00e1n excluidos del PBS aquellos elementos establecidos de manera expresa, taxativa y determinable en la normativa correspondiente180. Una interpretaci\u00f3n contraria infringir\u00eda el deber de otorgar el m\u00e1s alto nivel de salud posible181.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Respecto de su entrega en sede de tutela, se\u00f1al\u00f3 que, si el insumo no fue ordenado por el m\u00e9dico tratante, el juez de tutela deber\u00e1 verificar con la historia cl\u00ednica o con las pruebas allegadas al proceso, si la crema solicitada es necesaria para el tratamiento de la persona. De ser as\u00ed, ordenar\u00e1 su suministro con la condici\u00f3n de una posterior ratificaci\u00f3n por parte de un profesional de la salud. En caso de duda sobre la necesidad de proveer la crema anti-escaras, la autoridad judicial podr\u00e1 amparar el derecho a la salud en su faceta de diagn\u00f3stico. Para tal efecto, podr\u00e1 ordenar a la EPS que, a trav\u00e9s de una valoraci\u00f3n m\u00e9dica, determine la necesidad de prescribir la crema requerida en sede de tutela. Lo anterior, siempre que considere imperativo, a partir de un indicio razonable sobre la afectaci\u00f3n a la salud del accionante, otorgar una orden de protecci\u00f3n182. \u00a0 \u00a0<\/p>\n<p>Crema antipa\u00f1alitis \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En cuanto a la crema antipa\u00f1alitis, la Sala precisa que corresponde al nombre com\u00fan que reciben diferentes tipos de ung\u00fcentos para tratar la dermatitis irritativa del pa\u00f1al183. Este insumo puede definirse como una preparaci\u00f3n t\u00f3pica de barrera que impide el contacto de la piel con los agentes qu\u00edmicos y la humedad. Su uso minimiza la fricci\u00f3n y reduce los efectos de la enfermedad. Algunas de ellas, est\u00e1n compuestas por \u00f3xido de zinc, petrolato o ambas. En todo caso, otras incluyen agentes antimic\u00f3ticos como nistatina, clotrimazol, miconazol, ketoconazol y sertaconazol. Estas \u00faltimas se utilizan para tratar los casos en que existe una infecci\u00f3n secundaria por C\u00e1ndida184. De manera que, por su composici\u00f3n tampoco puede equipararse a la emulsi\u00f3n hidratante corporal185, ni a la loci\u00f3n hidratante corporal186, insumos excluidos del PBS.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por el contrario, la Sala advierte que algunos componentes que pueden encontrarse en las cremas antipa\u00f1alitis est\u00e1n expresamente incluidos en el PBS. Tal es el caso de la nistatina187 y el clotrimazol188. Estos agentes antimic\u00f3ticos hacen parte del plan en todas las concentraciones y formas farmac\u00e9uticas. Adicionalmente, en Sentencia T-528 de 2019189, esta Corporaci\u00f3n se\u00f1al\u00f3 que el \u00f3xido de zinc o cremas antipa\u00f1alitis hacen parte del PBS. Lo anterior, porque no est\u00e1 expresamente incluido en el anexo t\u00e9cnico de la Resoluci\u00f3n 244 de 2019190.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De lo expuesto, la Sala concluye que la crema antipa\u00f1alitis est\u00e1 incluida en el PBS. Por lo tanto, para su suministro son aplicables las reglas jurisprudenciales establecidas por la Sala Plena para la entrega de elementos que est\u00e1n cubiertos por el sistema de salud. Puntualmente, cuando el paciente no tiene orden m\u00e9dica, el juez deber\u00e1 corroborar, seg\u00fan las pruebas allegadas al proceso, si la crema solicitada es necesaria para el tratamiento de la persona. De ser as\u00ed, ordenar\u00e1 su suministro con la condici\u00f3n de una posterior ratificaci\u00f3n por parte de los m\u00e9dicos tratantes. De no contar con las pruebas mencionadas, el juez podr\u00e1 proteger el derecho a la salud en su faceta de diagn\u00f3stico. En ese caso, podr\u00e1 ordenar a la EPS que, mediante una valoraci\u00f3n m\u00e9dica, determine la necesidad de prescribir la crema requerida. Lo anterior, siempre que considere importante otorgar una orden de protecci\u00f3n, con ocasi\u00f3n de un indicio razonable sobre la afectaci\u00f3n del derecho a la salud del accionante191. \u00a0 \u00a0<\/p>\n<p>El transporte interurbano para acceder a servicios de salud \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Corte ha reconocido que el transporte no es una prestaci\u00f3n en s\u00ed misma. Por el contrario, es un mecanismo para acceder al servicio de salud192. Por esa raz\u00f3n, su falta de suministro puede desconocer la faceta de accesibilidad al sistema de salud reconocida en el literal c) del art\u00edculo 6\u00ba de la Ley Estatutaria de Salud193, lo que implica una vulneraci\u00f3n a los derechos fundamentales del paciente.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La Sala Sexta advierte que el transporte de pacientes fue incluido en el PBS, bajo ciertas condiciones194. En concreto, la normativa contempla el traslado acu\u00e1tico, a\u00e9reo y terrestre en ambulancia b\u00e1sica o medicalizada de pacientes cuando: (i) padecen una patolog\u00eda de urgencia que requiera su movilizaci\u00f3n, desde el sitio de ocurrencia de esta, hasta una instituci\u00f3n hospitalaria; (ii) son remitidos a otra IPS dentro del territorio nacional con ocasi\u00f3n de las limitantes de la oferta existente; o, (iii) son remitidos para atenci\u00f3n domiciliaria y el m\u00e9dico tratante as\u00ed lo prescribe195. Adicionalmente, establece que el transporte ambulatorio intermunicipal del usuario en un medio diferente a la ambulancia hace parte del PBS196. Lo anterior, siempre que requiera acceder a una atenci\u00f3n financiada con cargo a la UPC, que no est\u00e9 disponible en el lugar de residencia del afiliado197.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En aplicaci\u00f3n de las reglas descritas, la jurisprudencia ha reconocido que el transporte interurbano (traslados dentro del mismo municipio)198, en principio, no est\u00e1 cubierto por el PBS. Eso significa que el paciente o su red de apoyo deben asumir el costo correspondiente. En todo caso, la Sala advierte que dicha regla general tiene, al menos, dos excepciones. La primera es el traslado de pacientes remitidos para atenci\u00f3n domiciliaria. Seg\u00fan la normativa vigente, el PBS incluye expl\u00edcitamente el traslado en ambulancia b\u00e1sica o medicalizada de los pacientes remitidos para atenci\u00f3n domiciliaria. Lo anterior, siempre que cuente con una orden m\u00e9dica199.\u00a0 \u00a0 \u00a0<\/p>\n<p>La atenci\u00f3n domiciliaria es una modalidad extramural de prestaci\u00f3n del servicio de salud. En los t\u00e9rminos de la jurisprudencia, solo procede en casos de enfermedad en fase terminal y de enfermedad cr\u00f3nica, degenerativa e irreversible de alto impacto en la calidad de vida200. Es decir, en el caso de pacientes en situaciones extremadamente precarias de salud. De manera que su traslado a instituciones m\u00e9dicas, en caso de ser necesario, puede requerir transporte en ambulancia. Por esa raz\u00f3n, si el m\u00e9dico tratante lo considera necesario, prescribir\u00e1 la prestaci\u00f3n de ese servicio de traslado, el cual ser\u00e1 financiado con cargo a la UPC201.\u00a0 \u00a0<\/p>\n<p>En estos casos, el juez de tutela deber\u00e1 tener en cuenta las reglas aplicables para el suministro de insumos y servicios incluidos en el PBS. De esta manera, si el accionante no cuenta con prescripci\u00f3n m\u00e9dica, deber\u00e1n aplicarse las reglas contenidas en la Sentencia SU-508 de 2020202. \u00a0Esto quiere decir que deber\u00e1 analizar las pruebas allegadas al proceso. Si el traslado es necesario para el tratamiento de la persona, ordenar\u00e1 su suministro con la condici\u00f3n de una posterior ratificaci\u00f3n por parte de un profesional de la salud. En caso contrario, el juez podr\u00e1 amparar el derecho a la salud en su faceta de diagn\u00f3stico. Para el efecto, podr\u00e1 ordenar a la EPS que determine la necesidad de prescribir el transporte requerido en sede de tutela mediante una valoraci\u00f3n m\u00e9dica. Lo anterior, siempre que considere imperativo, a partir de un indicio razonable sobre la afectaci\u00f3n a la salud del demandante, otorgar una orden de protecci\u00f3n. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La segunda excepci\u00f3n est\u00e1 relacionada con aquellos casos en los que: (i) el m\u00e9dico tratante determin\u00f3 que el paciente necesita un servicio incluido en el PBS; (ii) el paciente y su red de apoyo no tienen los recursos necesarios para pagar el costo del traslado; y, (iii) de no efectuarse la remisi\u00f3n, se pone en riesgo la vida, la integridad o la salud del accionante203. En esos casos, ha dispuesto que los gastos de transporte del acompa\u00f1ante tambi\u00e9n pueden reconocerse204. Lo anterior, siempre que se pruebe que: (i) el paciente depende de un tercero totalmente para su movilizaci\u00f3n; (ii) el usuario requiere cuidado permanente para garantizar tanto su integridad f\u00edsica, como el ejercicio adecuado de sus labores cotidianas; y (iii) ni el paciente ni su familia tienen los recursos econ\u00f3micos para cubrir el transporte del tercero205. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En suma, conforme a la jurisprudencia, el juez de tutela puede ordenar que la EPS correspondiente suministre el transporte intermunicipal o interurbano del paciente y su acompa\u00f1ante, seg\u00fan lo requerido. Para el caso del transporte intermunicipal, bastar\u00e1 con verificar que el m\u00e9dico tratante prescribi\u00f3 un procedimiento que debe realizarse en un municipio distinto al de la residencia del paciente.\u00a0 \u00a0 \u00a0<\/p>\n<p>Para las solicitudes de transporte interurbano, primero, deber\u00e1 verificar si se trata de un paciente remitido para atenci\u00f3n domiciliaria. En ese evento, cuando el usuario tenga una prescripci\u00f3n m\u00e9dica, el juez conceder\u00e1 la prestaci\u00f3n del servicio. En su defecto, evaluar\u00e1 las pruebas allegadas al proceso. Si determina que el servicio es imprescindible lo ordenar\u00e1 con posterior ratificaci\u00f3n del profesional de la salud encargado. Por el contrario, si las pruebas no permitan establecer la necesidad del servicio, conceder\u00e1 el amparo en su faceta de derecho al diagn\u00f3stico.\u00a0 \u00a0<\/p>\n<p>Finalmente, en el evento en que el m\u00e9dico tratante no haya remitido al accionante para atenci\u00f3n domiciliaria, el juez podr\u00e1 conceder la prestaci\u00f3n del servicio de transporte para el usuario. Para el efecto, deber\u00e1 ver que: (i) existe imposibilidad de acudir a un medio de transporte adecuado ponga en peligro la vida, la integridad f\u00edsica o el estado de salud del usuario; y, (ii) ni el paciente, ni su familia cuentan con los recursos econ\u00f3micos para sufragar estos gastos. Este \u00faltimo requisito debe probarlo el actor. En todo caso, corresponde a la autoridad judicial determinar la procedencia del amparo invocado. Asimismo, podr\u00e1 autorizar la provisi\u00f3n de los gastos de transporte para un acompa\u00f1ante. En ese caso, el demandante tambi\u00e9n deber\u00e1 demostrar que el paciente depende completamente de un tercero para movilizarse y para garantizar tanto su integridad f\u00edsica, como el ejercicio adecuado de sus labores cotidianas.\u00a0 \u00a0<\/p>\n<p>Servicio de enfermer\u00eda \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Seg\u00fan esta Corporaci\u00f3n, el servicio de enfermer\u00eda corresponde al apoyo que podr\u00eda brindar el personal calificado en salud para la realizaci\u00f3n de algunos procedimientos. El m\u00e9dico tratante ser\u00e1 el encargado de determinar si la atenci\u00f3n del paciente requiere de la asistencia de un profesional de la salud. En ese evento, proferir\u00e1 la correspondiente orden m\u00e9dica206.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En Sentencia SU-508 de 2020207, la Sala Plena asegur\u00f3 que el servicio de enfermer\u00eda est\u00e1 incluido en el PBS. Expuso que hace parte de la modalidad de atenci\u00f3n domiciliaria208 y se circunscribe al \u00e1mbito de la salud. En todo caso, su prestaci\u00f3n solo procede en casos de enfermedad en fase terminal y de enfermedad cr\u00f3nica, degenerativa e irreversible de alto impacto en la calidad de vida209. Adicionalmente, se\u00f1al\u00f3 que este servicio no sustituye el de cuidador210. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En cuanto a su prestaci\u00f3n, precis\u00f3 que, si existe prescripci\u00f3n m\u00e9dica, el juez de tutela debe ordenarlo directamente. En caso contrario, podr\u00e1 ampararse el derecho a la salud en su faceta de diagn\u00f3stico. Lo anterior, siempre que advierta la necesidad de impartir una orden de protecci\u00f3n211. \u00a0 \u00a0<\/p>\n<p>Suministro de servicios e insumos excluidos del PBS sin prescripci\u00f3n m\u00e9dica \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Esta Corporaci\u00f3n ha reconocido que es posible que los pacientes soliciten por v\u00eda de tutela el suministro de insumos excluidos del PBS, sin tener una prescripci\u00f3n m\u00e9dica. En ese evento, el juez de tutela podr\u00e1 amparar el derecho a la salud del accionante en su faceta de diagn\u00f3stico. Para tal efecto, deber\u00e1 corroborar que existe un indicio razonable sobre la afectaci\u00f3n a la salud del paciente que amerite una orden de protecci\u00f3n212. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Esta regla resulta aplicable, por ejemplo, a las solicitudes de suministro de pa\u00f1itos h\u00famedos. La Sala Plena de esta Corporaci\u00f3n consider\u00f3 que ese insumo esta expl\u00edcitamente excluido del PBS, para todas las enfermedades o condiciones de salud. Lo anterior, porque as\u00ed lo dispuso el numeral 57 del anexo t\u00e9cnico de la Resoluci\u00f3n 244 de 2019213. En todo caso, advirti\u00f3 que su entrega puede otorgarse excepcionalmente en sede de tutela. Para tal efecto, el juez deber\u00e1 verificar que: (i) su provisi\u00f3n resulte necesaria para evitar la amenaza o vulneraci\u00f3n de los derechos a la vida o a la integridad personal del accionante214; (ii) los pa\u00f1itos h\u00famedos no puedan reemplazarse por otro insumo incluido en el PBS que tenga el mismo nivel de efectividad215; (iii) tanto el paciente, como su n\u00facleo familiar carecen de la capacidad econ\u00f3mica para asumir su costo216; y, (iv) fueron ordenados por el m\u00e9dico tratante adscrito a la EPS a la que se le solicita el suministro217.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Con todo, puede ocurrir que el actor no cuente con una prescripci\u00f3n m\u00e9dica. En ese evento, el juez de tutela podr\u00e1 amparar el derecho a la salud en su faceta de diagn\u00f3stico. Para tal efecto, deber\u00e1 corroborar que existe un indicio razonable sobre la afectaci\u00f3n a la salud del demandante que amerite una orden de protecci\u00f3n218. \u00a0 \u00a0<\/p>\n<p>1. En conclusi\u00f3n, cuando el accionante solicita la prestaci\u00f3n de servicios y el suministro de insumos de salud, sin contar con prescripci\u00f3n m\u00e9dica, el juez de tutela deber\u00e1 analizar las pruebas allegadas al proceso. De advertir que los elementos solicitados son indispensables para el paciente y hacen parte del PBS, podr\u00e1 ordenar su suministro. Sin embargo, supeditar\u00e1 la orden a su posterior ratificaci\u00f3n por parte del profesional de la salud encargado. Por el contrario, si las pruebas no permiten establecer que los insumos son necesarios, amparar\u00e1 el derecho en su faceta de diagn\u00f3stico. Estas reglas son aplicables para la entrega de sillas de ruedas, crema anti-escaras, crema antipa\u00f1alitis, y la prestaci\u00f3n del servicio de transporte de pacientes remitidos para atenci\u00f3n domiciliaria. Respecto del servicio de enfermer\u00eda, la Sala Plena estableci\u00f3 que, si el paciente no cuenta con orden m\u00e9dica, la autoridad judicial podr\u00e1 amparar el derecho en su faceta de diagn\u00f3stico. De igual forma, deber\u00e1 proceder si los elementos solicitados no hacen parte del PBS, como en el caso de los pa\u00f1itos h\u00famedos. En conclusi\u00f3n, cuando el paciente solicite en sede de tutela el suministro de servicios e insumos de salud sin prescripci\u00f3n m\u00e9dica y, de las pruebas allegadas no sea posible establecer su necesidad, el juez de tutela amparar\u00e1 el derecho a la salud en su faceta de derecho al diagn\u00f3stico.\u00a0 \u00a0 \u00a0<\/p>\n<p>Soluci\u00f3n al caso concreto\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En esta oportunidad, la Corte estudia la acci\u00f3n de tutela presentada por Fraddy Corredor Morales, en calidad de agente oficiosa de su madre, la se\u00f1ora Ana Elvia Morales de Corredor, contra FAMISANAR EPS. La agenciada tiene 86 a\u00f1os. Seg\u00fan su historia cl\u00ednica, depende por completo de un tercero para desarrollar sus actividades diarias como ba\u00f1arse, alimentarse y vestirse219. En todo caso, los m\u00e9dicos tratantes no le prescribieron los servicios m\u00e9dicos de enfermer\u00eda 24 horas y de transporte especial y\/o ambulancia, as\u00ed como el suministro de silla de ruedas, pa\u00f1itos h\u00famedos, crema antipa\u00f1alitis, crema anti-escaras y crema para piel diab\u00e9tica. Por esa raz\u00f3n, la agente oficiosa solicit\u00f3 directamente a FAMISANAR EPS la prestaci\u00f3n del servicio de enfermer\u00eda 24 horas para su madre220. La accionada neg\u00f3 la petici\u00f3n221. En atenci\u00f3n a la situaci\u00f3n de su madre, la agente insisti\u00f3 en su solicitud. Sin embargo, su petici\u00f3n no fue atendida222. Al d\u00eda siguiente de la presentaci\u00f3n del segundo escrito, la agenciada sufri\u00f3 un accidente que agrav\u00f3 sus condiciones de salud. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En el presente asunto, la Sala considera que FAMISANAR EPS vulner\u00f3 el derecho fundamental a la salud de la agenciada, en su faceta de derecho al diagn\u00f3stico. A continuaci\u00f3n, presenta las razones que soportan dicha conclusi\u00f3n. \u00a0 \u00a0<\/p>\n<p>FAMISANAR EPS desconoci\u00f3 que ante la ausencia de prescripciones m\u00e9dicas deb\u00eda adelantar las gestiones propias para garantizar el derecho al diagn\u00f3stico de la agenciada \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. La titular de los derechos es una persona de la tercera edad, puesto que tiene 86 a\u00f1os y, super\u00f3 la expectativa de vida promedio en Colombia223. De conformidad con la jurisprudencia, este grupo poblacional tiene derecho a una protecci\u00f3n constitucional reforzada en salud. Por lo tanto, los servicios e insumos de salud que requieran deben garantizarse de manera continua, oportuna, permanente y eficiente224. Asimismo, el Legislador estatutario se\u00f1al\u00f3 que su atenci\u00f3n en salud no puede limitarse por restricciones administrativas, ni econ\u00f3micas225. De manera que cualquier desconocimiento de estas reglas de protecci\u00f3n conllevan vulneraci\u00f3n del derecho a la salud. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De las pruebas aportadas al proceso, es posible establecer que los m\u00e9dicos tratantes no ordenaron la provisi\u00f3n de los servicios e insumos solicitados en sede de tutela. Por esa raz\u00f3n, la agente solicit\u00f3 directamente a FAMISANAR EPS, el 13 de noviembre de 2019, la prestaci\u00f3n del servicio de enfermer\u00eda 24 horas para su madre226. La entidad neg\u00f3 la petici\u00f3n el 4 de diciembre siguiente227. En atenci\u00f3n a la situaci\u00f3n de su madre, el 25 de enero de 2020, la agente insisti\u00f3 en su petici\u00f3n. Adicionalmente, requiri\u00f3 que les permitieran a los m\u00e9dicos tratantes ordenar los servicios y tecnolog\u00edas de salud que la accionante necesitaba. Esto, sin importar si est\u00e1n o no incluidas en el PBS228. En todo caso, su petici\u00f3n no fue atendida229. Al d\u00eda siguiente de la presentaci\u00f3n del segundo escrito, la agenciada sufri\u00f3 un accidente que agrav\u00f3 sus condiciones de salud. De tal modo que la agente se vio obligada a solicitar por v\u00eda de tutela el suministro de los servicios e insumos que, a su juicio, requer\u00eda su madre.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Al responder el escrito de tutela, FAMISANAR EPS afirm\u00f3 que no pod\u00eda proveer los insumos y servicios solicitados. Lo anterior, porque solo le corresponde autorizar la entrega de los elementos de salud prescritos por los m\u00e9dicos tratantes. En principio, la respuesta otorgada por la EPS tiene un fundamento razonable. Esto en el entendido que es el profesional de la salud quien cuenta con el conocimiento necesario para determinar qu\u00e9 prestaciones requiere la paciente.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Sin embargo, ante los padecimientos de la agenciada y la ausencia de orden m\u00e9dica, la entidad debi\u00f3 adelantar las gestiones administrativas correspondientes para garantizar el derecho al diagn\u00f3stico de la paciente. Desde finales del 2019, la agente oficiosa le solicit\u00f3 a la entidad proveer el servicio de auxiliar de enfermer\u00eda 24 horas. La entidad neg\u00f3 la solicitud porque no exist\u00eda orden m\u00e9dica. En atenci\u00f3n a lo anterior, pidi\u00f3 que se hicieran los ajustes para que los m\u00e9dicos tratantes ordenaran el suministro de los insumos y servicios requeridos por la accionante. En todo caso, la accionada guard\u00f3 silencio. A juicio de la Sala, esa situaci\u00f3n constituy\u00f3 una barrera para el ejercicio de los derechos a la salud y a la vida digna por la omisi\u00f3n administrativa, para prestar el servicio de salud a la paciente. Lo anterior, porque, de un lado, no pudo acceder a los elementos que consideraba necesarios para garantizar su salud y vida en condiciones dignas. Y, de otro, tampoco pudo obtener una valoraci\u00f3n m\u00e9dica, t\u00e9cnica, cient\u00edfica y oportuna de su estado de salud.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Adicionalmente, esa situaci\u00f3n le impidi\u00f3 a la accionante conocer informaci\u00f3n relevante sobre el tratamiento de su condici\u00f3n de salud. En concreto, la falta de diagn\u00f3stico le impidi\u00f3 conocer si requer\u00eda o no la prestaci\u00f3n de los servicios m\u00e9dicos de enfermer\u00eda 24 horas y de transporte especial y\/o ambulancia, as\u00ed como el suministro de silla de ruedas, pa\u00f1itos h\u00famedos, crema antipa\u00f1alitis, crema anti-escaras y crema para piel diab\u00e9tica. En particular, el impacto de dichos insumos en el tratamiento de su enfermedad y en el mejoramiento de su calidad de vida.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ahora bien, la Sala destaca que las pruebas allegadas al proceso no permit\u00edan establecer con certeza que los elementos solicitados eran procedentes para el tratamiento de la agenciada. La agente oficiosa present\u00f3 al proceso varias valoraciones m\u00e9dicas de su madre230. Esos documentos daban cuenta de diferentes padecimientos de la usuaria, tales como: \u201cenfermedad cerebrovascular, no especificada, e109 diabetes mellitus insulinodependiente, f002 demencia en la enfermedad de Alzheimer, at\u00edpica o de tipo mixto, s099 traumatismo de la cabeza, no especificado, r32x incontinencia urinaria, s\u00edndrome demencial mixto, secuela probable acv frontal bilateral, infarto cerebral no especificado, sincope probable de origen cardiovascular, s\u00edndrome de la alteraci\u00f3n de la conciencia, hipertensi\u00f3n arterial hta estadio 2 controlada, insuficiencia cardiaca cr\u00f3nica, deshidrataci\u00f3n hipert\u00f3nica dht tipo ii, antc de fractura de cadera derecha pop de osteos\u00edntesis de cadera derecha en jun 2018, conjuntivitis bacteriana, desnutrici\u00f3n severa\u201d231. Por su parte, la EPS manifest\u00f3 que los m\u00e9dicos tratantes no ordenaron los insumos y servicios requeridos.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Las patolog\u00edas descritas en los documentos allegados reflejan el precario estado de salud de la accionante. De igual manera, permiten advertir que probablemente la agenciada requiere los elementos solicitados en sede de tutela. Sin embargo, no son suficientes para que el juez de tutela establezca con certeza: (i) la oportunidad de esos servicios e insumos en el tratamiento de las patolog\u00edas de la paciente; (ii) qu\u00e9 tipo de elemento de salud es el apropiado para la paciente, en t\u00e9rminos de componentes y aspectos t\u00e9cnicos; y, (iii) la periodicidad de su suministro. Lo anterior, por las razones que se exponen a continuaci\u00f3n.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Respecto de la solicitud de otorgar una silla de ruedas, la informaci\u00f3n de las historias cl\u00ednicas es confusa. De un lado, establece que la paciente no puede permanecer sentada. Y, de otro, que puede trasladarse de manera independiente por medio de una silla de ruedas232. Por tal raz\u00f3n, ni el juez de instancia, ni la Sala ten\u00edan la posibilidad de establecer con claridad la procedencia de dicho elemento y sus especificaciones t\u00e9cnicas para la especial condici\u00f3n de la paciente.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En cuanto al suministro de cremas anti-escaras, antipa\u00f1alitis y para piel diab\u00e9tica, la historia cl\u00ednica precisa que la accionante padece incontinencia mixta, diabetes y problemas de movilidad. Esas patolog\u00edas, a su vez, est\u00e1n relacionadas con otros padecimientos cuyo tratamiento puede necesitar el uso de los ung\u00fcentos mencionados. En ese sentido, el tratamiento de la incontinencia mixta podr\u00eda requerir el uso de crema antipa\u00f1alitis. En todo caso, los componentes que deba tener ese insumo y, la periodicidad de su aplicaci\u00f3n, depender\u00e1n del tipo de la lesi\u00f3n que la dermatitis ocasione en la piel del paciente.\u00a0 \u00a0 \u00a0<\/p>\n<p>Finalmente, en relaci\u00f3n con la crema anti-escaras, la historia cl\u00ednica indic\u00f3 que la agenciada tiene problemas de movilidad y depende por completo de un tercero para desarrollar sus actividades diarias. Esto permite inferir que probablemente requiere del insumo mencionado. No obstante, ni el juez de instancia ni la Sala pueden determinar con certeza la oportunidad de suministrar ese elemento, los componentes que el insumo deber\u00eda tener ni la periodicidad de su uso.\u00a0 \u00a0<\/p>\n<p>De conformidad con lo anterior, el suministro de las cremas mencionadas requiere del concepto t\u00e9cnico y cient\u00edfico del profesional de la salud. Al no contar con ello, le corresponde a la Sala amparar el derecho a la salud y a la vida digna de la accionante, en su faceta de diagn\u00f3stico.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Referente a la entrega de pa\u00f1itos h\u00famedos, la historia cl\u00ednica advierte que la agenciada padece incontinencia mixta. La jurisprudencia ha reconocido que la falta de uso de este elemento en pacientes que tienen limitaciones para realizar aut\u00f3nomamente sus necesidades fisiol\u00f3gicas puede ocasionar otros padecimientos. A manera de ejemplo, se\u00f1al\u00f3 que puede generar infecciones urinarias, Dermatitis Asociada a la Incontinencia (DAI), lesiones de la piel con p\u00e9rdida progresiva de la misma y lesiones cr\u00f3nicas con infecciones cut\u00e1neas. De no ser atendidas oportuna y apropiadamente, estas \u00faltimas pueden llevar a la sepsis, e incluso, a la muerte en casos extremos234. Sin embargo, los elementos se\u00f1alados en la historia cl\u00ednica son insuficientes para establecer los componentes que debe tener ese elemento, as\u00ed como la periodicidad de su uso235.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Finalmente, la agente oficiosa solicit\u00f3 la prestaci\u00f3n de los servicios de enfermer\u00eda 24 horas diarias y el transporte especial o en ambulancia para su madre. Las historias cl\u00ednicas allegadas no se\u00f1alan expresamente que la agenciada requiera de procedimientos t\u00e9cnicos que deban ejecutarse por profesionales de la salud durante el d\u00eda. Tampoco establecen que tuviera que asistir a instituciones hospitalarias para la prestaci\u00f3n del servicio de salud. Por el contrario, afirman que la accionante hace parte del programa de m\u00e9dico domiciliario de la EPS236. Esos elementos no permiten al juez de instancia, ni a la Sala, determinar con precisi\u00f3n qu\u00e9 tipo de servicios requiere la usuaria. Por ejemplo, no es posible establecer si la paciente necesita la prestaci\u00f3n de los servicios de una persona graduada en enfermer\u00eda o en auxiliar de enfermer\u00eda. Asimismo, se desconoce si el transporte de la usuaria requiera una ambulancia medicalizada o no. Adicionalmente, en relaci\u00f3n con el servicio de enfermer\u00eda, esta Corporaci\u00f3n estableci\u00f3 que, cuando el paciente no cuenta con prescripci\u00f3n m\u00e9dica para ese servicio, el juez de tutela debe amparar el derecho en su faceta de derecho al diagn\u00f3stico. Por lo tanto, el juez de tutela no pod\u00eda otorgar servicios requeridos por la agente oficiosa.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. En conclusi\u00f3n, las valoraciones m\u00e9dicas aportadas configuraban un indicio razonable sobre la afectaci\u00f3n del derecho a la salud de la agenciada. Por esa raz\u00f3n, lo que correspond\u00eda era amparar ese derecho fundamental en su faceta de diagn\u00f3stico. Por tal raz\u00f3n, la Sala confirmar\u00e1 la decisi\u00f3n del juez de \u00fanica instancia, por medio de la cual ampar\u00f3 los derechos a la salud y a la vida digna de la agenciada, en dicha faceta.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>1. De otra parte, las pruebas aportadas en sede de revisi\u00f3n permiten a la Sala advertir que, con ocasi\u00f3n del fallo de instancia, la agenciada fue valorada por los m\u00e9dicos tratantes el 29 de septiembre y el 7 de octubre de 2021. En esas oportunidades, le prescribieron algunos de los insumos y servicios solicitados por la agenciada en sede de tutela. Puntualmente, el servicio de enfermer\u00eda 24 horas diarias, pa\u00f1itos h\u00famedos, crema antipa\u00f1alitis nistatina, crema anti-escaras \u201cmarly\u201d y transporte redondo puerta a puerta en ambulancia b\u00e1sica para asistir a citas m\u00e9dicas o estudios, cuando se requiera. \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Sin embargo, de un lado, la agente asegur\u00f3 que la EPS no le ha suministrado los elementos e insumos de salud prescritos a su madre. De igual manera, la accionada no acredit\u00f3 la entrega de los mismos en las contestaciones aportadas en sede de revisi\u00f3n. Y, del otro, los diagn\u00f3sticos aportados no contienen pronunciamientos respecto de la pertinencia de proveer crema para piel diab\u00e9tica y una silla de ruedas para la agenciada. En su intervenci\u00f3n del 26 de octubre de 2021, la accionada manifest\u00f3 que la profesional de la salud encargada no prescribi\u00f3 la silla de ruedas. Por esa raz\u00f3n, agend\u00f3 una cita m\u00e9dica en IPS ortop\u00e9dicos Chapinero, para el viernes 5 de noviembre a las 11:30 a.m. Lo anterior, para determinar la pertinencia de prescribir este insumo237. En todo caso, no alleg\u00f3 copia de la programaci\u00f3n del procedimiento. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por lo anterior, la Sala considera que la vulneraci\u00f3n del derecho a la salud de la agenciada persiste. En ese sentido, ordenar\u00e1 a la accionada que, si a\u00fan no lo ha hecho: (i) suministre los pa\u00f1itos h\u00famedos, la crema antipa\u00f1alitis nistatina, y la crema anti-escaras \u201cmarly\u201d en las condiciones prescritas por el m\u00e9dico tratante; y, (ii) realice las actuaciones correspondientes para que, a trav\u00e9s de los m\u00e9dicos adscritos a su red de prestadores, valore nuevamente a la agenciada. En esta oportunidad, los profesionales de la salud deber\u00e1n determinar si la accionante requiere: (i) crema para piel diab\u00e9tica; y, (ii) una silla de ruedas o cualquier otra ayuda t\u00e9cnica que mejore su movilidad. Lo anterior, con el fin de que la titular de los derechos pueda acceder al elemento que mejor garantice su derecho a la salud y a la vida digna. \u00a0 \u00a0 \u00a0<\/p>\n<p>Adicionalmente, para materializar el derecho a la informaci\u00f3n y a la autodeterminaci\u00f3n en salud de la agenciada, los profesionales de la salud que realicen la valoraci\u00f3n de la paciente deber\u00e1n manifestar expresamente las razones por las cuales la demandante requiere o no de los elementos mencionados.\u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Finalmente, en relaci\u00f3n con la pretensi\u00f3n de tratamiento integral, la Sala advierte que no existe claridad sobre el tratamiento que ameritan las patolog\u00edas de la agenciada. Tal y como se estableci\u00f3 con anterioridad, la EPS, a trav\u00e9s de los m\u00e9dicos adscritos a su red de prestadores del servicio, no ha valorado todas las condiciones de salud de la paciente. Aquello impide que la Sala tenga certeza respecto de su tratamiento. De manera que otorgar el amparo en ese sentido implicar\u00eda pronunciarse sobre situaciones futuras e inciertas. Por lo tanto, no procede conceder esa solicitud.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00d3rdenes por proferir \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. De conformidad con lo expuesto, la Sala Sexta de Revisi\u00f3n confirmar\u00e1 la sentencia del 29 de julio de 2021, proferida por el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1. Aquella tutel\u00f3 los derechos fundamentales a la salud y a la vida en condiciones dignas, de la accionante en su faceta de acceso al diagn\u00f3stico. Adicionalmente, le ordenar\u00e1 a la EPS que, si a\u00fan no lo ha hecho, dentro de las veinticuatro (24) horas siguientes a la notificaci\u00f3n de esta decisi\u00f3n, autorice y entregue a la accionante los pa\u00f1itos h\u00famedos, la crema antipa\u00f1alitis nistatina y la crema anti-escaras \u201cmarly\u201d prescritos por los m\u00e9dicos tratantes en las condiciones establecidas por la orden m\u00e9dica. De igual manera que, en caso de no haberlo hecho, dentro de las cuarenta y ocho (48) horas siguientes a la notificaci\u00f3n de esta decisi\u00f3n, valore, a trav\u00e9s de los profesionales de la salud adscritos a su entidad, si la agenciada requiere crema para piel diab\u00e9tica y una silla de ruedas o cualquier otra ayuda t\u00e9cnica que mejore su movilidad.\u00a0 \u00a0 \u00a0<\/p>\n<p>Dentro del concepto m\u00e9dico, los profesionales de la salud encargados de valorar a la agenciada deber\u00e1n justificar, de manera clara y comprensible, si la se\u00f1ora Ana Elvia requiere o no la crema para piel diab\u00e9tica y\/o alguna ayuda t\u00e9cnica para movilizarse y de qu\u00e9 tipo. En el evento en que, los m\u00e9dicos tratantes prescriban la crema para piel diab\u00e9tica y\/o una silla de ruedas u otra ayuda t\u00e9cnica, FAMISANAR EPS deber\u00e1 garantizar la entrega de esos elementos dentro de los diez (10) d\u00edas h\u00e1biles siguientes a la prescripci\u00f3n m\u00e9dica.\u00a0 \u00a0<\/p>\n<p>Finalmente, oficiar\u00e1 a la Procuradur\u00eda General de la Naci\u00f3n para que, en el \u00e1mbito de sus competencias constitucionales238, acompa\u00f1e el cumplimiento de esta providencia. De igual manera, ordenar\u00e1 a la accionada que, dentro de los veinte (20) d\u00edas h\u00e1biles siguientes a la notificaci\u00f3n de esta decisi\u00f3n, remita un informe detallado sobre el cumplimiento de las \u00f3rdenes dispuestas en esta providencia judicial al Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1, quien conoci\u00f3 en \u00fanica instancia de este caso239. Lo anterior, para que esa autoridad judicial en el marco de sus competencias realice el seguimiento al cumplimiento de esta providencia240. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Luego de establecer la procedencia de la acci\u00f3n de tutela, la Sala estudi\u00f3 si la EPS demandada vulner\u00f3 el derecho a la salud de su afiliada, al negar la autorizaci\u00f3n de varios insumos y servicios de salud, con fundamento en que los m\u00e9dicos tratantes no los ordenaron.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Para resolver esa cuesti\u00f3n, reiter\u00f3 la jurisprudencia sobre: el derecho a la salud de las personas de la tercera edad; (ii) la figura del tratamiento integral; (iii) el derecho al diagn\u00f3stico; y, (iv) las reglas jurisprudenciales sobre el suministro de los servicios de enfermer\u00eda o auxiliar de enfermer\u00eda y de transporte interurbano, as\u00ed como de silla de ruedas, pa\u00f1itos h\u00famedos, crema anti-escaras y antipa\u00f1alitis. Record\u00f3 que los servicios e insumos de salud que requieran las personas de la tercera deben garantizarse de manera continua, oportuna, permanente y eficiente. Esto sin anteponer barreras de orden administrativo. En relaci\u00f3n con la provisi\u00f3n de los servicios e insumos mencionados, en sede de tutela, se\u00f1al\u00f3 que el juez debe analizar las pruebas aportadas al proceso. Si de ellas no logra concluir que los insumos y servicios son necesarios para el paciente, entonces deber\u00e1 amparar el derecho a la salud en su faceta de diagn\u00f3stico.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. A partir de la informaci\u00f3n recaudada en el proceso, la Sala encontr\u00f3 que la EPS accionada vulner\u00f3 el derecho a la salud de la agenciada, en su faceta de diagn\u00f3stico. En efecto, constat\u00f3 que: (i) la demandante es un sujeto de especial protecci\u00f3n constitucional y no contaba con orden m\u00e9dica para los insumos y servicios solicitados en sede de tutela. Por esa raz\u00f3n, (ii) solicit\u00f3 a la EPS proveer algunos de los servicios requeridos y permitir que los m\u00e9dicos tratantes prescribieran lo solicitado. En todo caso, (iii) la accionada no adelant\u00f3 las gestiones para determinar si los insumos y servicios eran necesarios para tratar las patolog\u00edas de la accionante. Adicionalmente, (iv) de las pruebas aportadas no era posible establecer con certeza la oportunidad de prescribir los insumos y servicios particulares que fueron solicitados. Tampoco permit\u00edan determinar el tipo de elemento o servicio pertinente ni la periodicidad de su provisi\u00f3n. Por lo tanto, lo que procede en este caso es amparar los derechos a la salud y a la vida digna, en su faceta de diagn\u00f3stico.\u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por otra parte, constat\u00f3 que, para el momento de este fallo, la agenciada fue valorada por los m\u00e9dicos tratantes. En consecuencia, le prescribieron el servicio de enfermer\u00eda 24 horas diarias, pa\u00f1itos h\u00famedos, crema antipa\u00f1alitis nistatina, crema anti-escaras \u201cmarly\u201d y transporte redondo puerta a puerta en ambulancia b\u00e1sica para asistir a citas m\u00e9dicas o estudios, cuando se requiera. No obstante, la accionada no los ha suministrado y los diagn\u00f3sticos aportados no contienen pronunciamientos respecto de la pertinencia de proveer crema para piel diab\u00e9tica y una silla de ruedas a la usuaria. Por lo anterior, la Sala considera que la vulneraci\u00f3n del derecho a la salud de la agenciada contin\u00faa. En ese sentido, esta Sala le ordenar\u00e1 a la EPS que, si a\u00fan no lo ha hecho, dentro de las veinticuatro (24) horas siguientes a la notificaci\u00f3n de esta decisi\u00f3n, autorice y entregue los elementos de salud prescritos por los m\u00e9dicos tratantes. De igual manera que, en caso de no haberlo hecho, dentro de las cuarenta y ocho (48) horas siguientes a la notificaci\u00f3n de esta decisi\u00f3n, valore, a trav\u00e9s de los profesionales de la salud adscritos a su entidad, si la demandante requiere crema para piel diab\u00e9tica y una silla de ruedas o cualquier otra ayuda t\u00e9cnica que mejore su movilidad. Los profesionales de la salud que realicen la valoraci\u00f3n de la paciente deber\u00e1n manifestar expresamente las razones por las cuales la accionante requiere o no de los elementos mencionados.\u00a0 \u00a0 \u00a0<\/p>\n<p>Adicionalmente, la Sala oficiar\u00e1 a la Procuradur\u00eda General de la Naci\u00f3n para que acompa\u00f1e el cumplimiento de esta providencia. De igual manera, ordenar\u00e1 a la accionada que, dentro de los veinte (20) d\u00edas h\u00e1biles siguientes a la notificaci\u00f3n de esta decisi\u00f3n, remita un informe detallado sobre el cumplimiento de las \u00f3rdenes dispuestas en esta providencia judicial al Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1, quien conoci\u00f3 en \u00fanica instancia de este caso. Lo anterior, para que esa autoridad judicial en el marco de sus competencias realice el seguimiento al cumplimiento de esta providencia. \u00a0<\/p>\n<p>III. DECISI\u00d3N\u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Sexta de Revisi\u00f3n de la Corte Constitucional, administrando justicia en nombre del Pueblo y por mandato de la Constituci\u00f3n Pol\u00edtica, \u00a0<\/p>\n<p>RESUELVE \u00a0<\/p>\n<p>PRIMERO. &#8211; CONFIRMAR la sentencia del 29 de julio de 2021, proferida, en \u00fanica instancia, por el por el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1, que TUTEL\u00d3 los derechos fundamentales a la salud y a la vida en condiciones dignas, en su faceta de acceso al diagn\u00f3stico de la se\u00f1ora Ana Elvia Morales de Corredor. \u00a0<\/p>\n<p>SEGUNDO. &#8211; ORDENAR a FAMISANAR EPS que, si a\u00fan no lo ha hecho, dentro de las veinticuatro (24) horas siguientes a la notificaci\u00f3n de esta decisi\u00f3n, autorice y entregue a la agenciada los insumos m\u00e9dicos prescritos por los m\u00e9dicos tratantes en la valoraci\u00f3n m\u00e9dica del 7 de octubre de 2021. Para tal efecto, la demandada deber\u00e1 remover todos los obst\u00e1culos administrativos y adelantar\u00e1 las gestiones necesarias para tal fin.\u00a0 \u00a0<\/p>\n<p>TERCERO. &#8211; ORDENAR a FAMISANAR EPS que, si a\u00fan no lo ha hecho, dentro de las cuarenta y ocho (48) horas siguientes a la notificaci\u00f3n de esta decisi\u00f3n, valore, a trav\u00e9s de los profesionales de la salud adscritos a su entidad, si la agenciada requiere crema para piel diab\u00e9tica y una silla de ruedas o cualquier otra ayuda t\u00e9cnica que mejore su movilidad.\u00a0 \u00a0<\/p>\n<p>Dentro del concepto m\u00e9dico, los profesionales de la salud encargados de la valoraci\u00f3n deber\u00e1n justificar, de manera clara, si la paciente requiere o no crema para piel diab\u00e9tica y\/o alguna ayuda t\u00e9cnica para movilizarse y de qu\u00e9 tipo. En el evento en que los m\u00e9dicos tratantes prescriban la crema para piel diab\u00e9tica y\/o una silla de ruedas u otra ayuda t\u00e9cnica, FAMISANAR EPS deber\u00e1 garantizar la entrega de esos elementos dentro de los diez (10) d\u00edas h\u00e1biles siguientes a la prescripci\u00f3n m\u00e9dica.\u00a0 \u00a0<\/p>\n<p>CUARTO. \u2013 ORDENAR que, por Secretar\u00eda General de la Corte, se oficie a la Procuradur\u00eda General de la Naci\u00f3n, para que, dentro del \u00e1mbito de sus competencias constitucionales y legales, acompa\u00f1e el cumplimiento de esta sentencia. \u00a0<\/p>\n<p>QUINTO. \u2013 ORDENAR a FAMISANAR EPS que, dentro de los veinte (20) d\u00edas h\u00e1biles siguientes a la notificaci\u00f3n de esta decisi\u00f3n, remita un informe detallado sobre el cumplimiento de las \u00f3rdenes dispuestas en los numerales segundo y tercero de esta providencia al Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1, quien conoci\u00f3 en \u00fanica instancia de este caso. Lo anterior, para que esa autoridad judicial en el marco de sus competencias realice el seguimiento correspondiente al cumplimiento de esta providencia. \u00a0<\/p>\n<p>SEXTO. \u2013 Por Secretar\u00eda General de la Corte Constitucional, L\u00cdBRESE la comunicaci\u00f3n prevista en el art\u00edculo 36 del Decreto 2591 de 1991. \u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese y c\u00famplase. \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>CRISTINA PARDO SCHLESINGER \u00a0<\/p>\n<p>Magistrada \u00a0<\/p>\n<p>JOS\u00c9 FERNANDO REYES CUARTAS \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA M\u00c9NDEZ \u00a0<\/p>\n<p>Secretaria General \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 El Juzgado Veintitr\u00e9s Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 remiti\u00f3 el caso a la Corte el 13 de marzo de 2020. Oficio No. 225 del 13 de marzo de 2020. En expediente. Cuaderno 1. Folio 1.\u00a0 \u00a0<\/p>\n<p>2 \u201cAUTO SALA DE SELECCI\u00d3N 16 DE ABRIL DE 2021 NOTIFICADO 03 DE MAYO DE 2021.pdf\u201d. Folio 13. Numeral 10. \u00a0<\/p>\n<p>3 M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>4 Por medio del cual el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 remiti\u00f3 el expediente a la Corte Constitucional sin el tr\u00e1mite de impugnaci\u00f3n correspondiente. Expediente. Cuaderno 1. Folio 1.\u00a0 \u00a0<\/p>\n<p>5 Escrito de tutela. En expediente. Cuaderno 1. Folio 26.\u00a0 \u00a0<\/p>\n<p>6 Ibid. \u00a0<\/p>\n<p>7 Fotocopia de la c\u00e9dula de ciudadan\u00eda de Ana Elvia Morales de Corredor. En expediente. Cuaderno 1. Folio 33.\u00a0 \u00a0<\/p>\n<p>8 Valoraci\u00f3n m\u00e9dica del 7 de octubre de 2021. En expediente. Documento remitido por correo electr\u00f3nico: \u201cHistoria cl\u00ednica domiciliarios.pdf\u201d. Folios16 a 22. \u00a0<\/p>\n<p>9 \u201cCertificaci\u00f3n expedida para efectos de cumplimiento de la Ley 361 de 1997 y adquisici\u00f3n de derechos a beneficios por parte de los discapacitados\u201d. En expediente. Cuaderno 1. Folio 32. \u00a0<\/p>\n<p>10 Como beneficiaria del r\u00e9gimen contributivo, desde el 1\u00ba de agosto de 2005.\u00a0 \u00a0<\/p>\n<p>11 Escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folios 4 y 5. \u00a0<\/p>\n<p>12 Ibid. Folio 5. \u00a0<\/p>\n<p>13 Fotocopia de los documentos de identidad de los integrantes del n\u00facleo familia. En expediente. Cuaderno 1. Folios del 33 al 38.\u00a0 \u00a0<\/p>\n<p>14 Ibid. \u00a0 \u00a0<\/p>\n<p>15 Escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folio 7. \u00a0<\/p>\n<p>16 La agente oficiosa en este proceso est\u00e1 encargada del cuidado de la titular de los derechos, de su padre, su t\u00eda, y sus hijos menores de edad de 10 y 15 a\u00f1os. Ibid. Folio 5. \u00a0<\/p>\n<p>17 Constancia de remisi\u00f3n por orientaci\u00f3n escolar. En expediente. Cuaderno 1. Folio 39. \u00a0<\/p>\n<p>18 Escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folio 7. \u00a0<\/p>\n<p>19 Derecho de petici\u00f3n Q-841962 del 13 de noviembre de 2019. En expediente. Cuaderno 1. Folios 29 y 30.\u00a0 \u00a0<\/p>\n<p>20 Respuesta de FAMISANAR E.P.S. a queja de radicado Q-841962. En expediente. Cuaderno 1. Folio 40.\u00a0 \u00a0<\/p>\n<p>21 Transcrito en escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folio 6. \u00a0<\/p>\n<p>22 Mencionado en escrito de acci\u00f3n de tutela. Ibid. Folio 6. \u00a0<\/p>\n<p>23 Historia cl\u00ednica proferida por National Clinics Centenario S.A.S. En expediente. Cuaderno 1. Folios del 53 al 60.\u00a0 \u00a0<\/p>\n<p>24 Escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folios 6 y 7.\u00a0 \u00a0<\/p>\n<p>25 Ibid. Folios del 2 al 28.\u00a0 \u00a0<\/p>\n<p>26 Escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folios 27 y28.\u00a0 \u00a0<\/p>\n<p>27 Auto admisorio de la demanda. En expediente. Cuaderno 1. Folio 62. \u00a0<\/p>\n<p>28 En concreto, los servicios de enfermer\u00eda o auxiliar de enfermer\u00eda 24 horas diarias y de transporte especial o ambulancia, as\u00ed como el suministro de pa\u00f1itos, crema antipa\u00f1alitis, crema anti-escaras, crema para piel diab\u00e9tica y silla de ruedas.\u00a0 \u00a0<\/p>\n<p>29 Contestaci\u00f3n de la demanda. En expediente. Cuaderno 1. Folios del 67 al 76.\u00a0 \u00a0<\/p>\n<p>30 Ley 1751 de 2015 \u201cPor medio de la cual se regula el derecho fundamental a la salud y se dictan otras disposiciones\u201d; Resoluci\u00f3n 6408 de 2016 \u201cPor la cual se modifica el Plan de Beneficios en Salud con cargo a la Unidad de Pago por Capitaci\u00f3n (UPC)\u201d, proferida por el Ministerio de Salud y Protecci\u00f3n Social.\u00a0 \u00a0<\/p>\n<p>32 Ibid.\u00a0 \u00a0<\/p>\n<p>33 Ibid. \u00a0<\/p>\n<p>34 Los cuales corresponden a la prestaci\u00f3n de los servicios de enfermer\u00eda y\/o auxiliar de enfermer\u00eda 24 horas diarias y de transporte especial y\/o ambulancia, as\u00ed como el suministro de pa\u00f1itos, crema antipa\u00f1alitis, crema anti-escaras, crema para piel diab\u00e9tica y silla de ruedas.\u00a0 \u00a0<\/p>\n<p>35 Fallo de primera instancia. En expediente. Cuaderno 1. Folios del 82 al 88.\u00a0 \u00a0<\/p>\n<p>36 Ibid. Folios del 82 al 88. El 4 de marzo de 2020, el juez de primera instancia notific\u00f3 su decisi\u00f3n a Famisanar EPS y a la IPS Emmanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S Constancias de notificaci\u00f3n. En expediente electr\u00f3nico. En expediente. Cuaderno 1. Folios 89 y 90. \u00a0<\/p>\n<p>37 Impugnaci\u00f3n presentada por la accionante. En expediente. Cuaderno 1. Folios del 91 al 95.\u00a0 \u00a0<\/p>\n<p>38 Mediante correo electr\u00f3nico de Asunto: Env\u00edo respuesta enviado a despachogloriaortiz@corteconstitucional.gov.co y secretaria1@corteconstitucional.gov.co, el 21 de mayo de 2021.\u00a0 \u00a0<\/p>\n<p>39 En expediente. Cuaderno 1. Folio 1. \u00a0<\/p>\n<p>40 Explic\u00f3 que, en su momento, la secretaria del juzgado, en vez de remitir el recurso de apelaci\u00f3n a la segunda instancia, envi\u00f3 el expediente directamente a la Corte Constitucional. En la misma comunicaci\u00f3n, present\u00f3 el informe secretarial de 24 de mayo de 2021, por medio del cual se explica el error que dio origen a la irregularidad advertida. Oficio N\u00b0232 del 24 de mayo de 2021. En expediente. Cuaderno 2. Disponible en CD. Documento: \u201cOFICIO A LA CORTE CONSTITUCIONAL.pdf\u201d. \u00a0 \u00a0<\/p>\n<p>41 Auto del 24 de mayo de 2021, proferido por el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1. En expediente. Cuaderno 2. Disponible en CD. Documento: \u201cAUTO CONCEDE IMPUGNACI\u00d3N.pdf\u201d. \u00a0<\/p>\n<p>42 Por medio de correo electr\u00f3nico enviado el 2 de julio de 2021, a las direcciones electr\u00f3nicas despachogloriaortiz@corteconstitucional.gov.co y secretaria1@corteconstitucional.gov.co.\u00a0 \u00a0<\/p>\n<p>43 M.P. Gloria Stella Ortiz Delgado \u00a0<\/p>\n<p>44 Por medio del cual el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 remiti\u00f3 el expediente a la Corte Constitucional sin el tr\u00e1mite de impugnaci\u00f3n correspondiente. Expediente. Cuaderno 1. Folio 1.\u00a0 \u00a0<\/p>\n<p>45 Declar\u00f3\u201cla nulidad, por pretermisi\u00f3n de la segunda instancia, de todas las actuaciones surtidas en el proceso de tutela de la referencia a partir del Oficio No. 225 del 13 de marzo de 2020, inclusive, por medio del cual el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 remiti\u00f3 el expediente a la Corte Constitucional sin el tr\u00e1mite de apelaci\u00f3n correspondiente, salvo las actuaciones surtidas en sede de revisi\u00f3n, relacionadas con la selecci\u00f3n del caso y las pruebas recaudadas\u201d. Auto 318 de 2021, M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>46 Ver al respecto: Oficio N\u00b0 A-785\/2021 del 1 de julio de 2021.\u00a0 \u00a0<\/p>\n<p>47 En atenci\u00f3n a la comunicaci\u00f3n referida, el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1 suspendi\u00f3 la producci\u00f3n del nuevo fallo de primera instancia. Asimismo, en Oficio N\u00b0 283 del 1 de Julio de 2021, le solicit\u00f3 a la Oficina de Apoyo Judicial de Paloquemao \u2013 someter nuevamente a reparto el expediente de conformidad con la decisi\u00f3n adoptada por la Sala Sexta de Revisi\u00f3n. As\u00ed lo afirm\u00f3 el juez de instancia en el Oficio N\u00b0 301 de 29 de julio de 2021, En expediente. Cuaderno 2. Disponible en CD. Documento: \u201cOFICIO CORTE CONSTITUCIONAL TUTELA 039-2020.pdf\u201d. \u00a0<\/p>\n<p>48 Por medio de correo electr\u00f3nico enviado el 2 de julio de 2021, a las direcciones electr\u00f3nicas despachogloriaortiz@corteconstitucional.gov.co y secretaria1@corteconstitucional.gov.co.\u00a0 \u00a0<\/p>\n<p>49 Intervenci\u00f3n de IPS Hospital en Casa. En expediente. Cuaderno 2. Disponible en CD. Documento: \u201cRespuesta SINERGIA GLOBAL EN SALUD S.A.S.pdf\u201d. \u00a0<\/p>\n<p>50 As\u00ed lo manifest\u00f3 el juez de instancia en la Sentencia del 29 de julio de 2021. En expediente. Cuaderno 2. Disponible en CD. Documento: \u201cFALLO TUTELA 039-2020 DESPU\u00c9S DE NULIDAD.pdf\u201d. \u00a0<\/p>\n<p>51 Sentencia del 29 de julio de 2021, proferida por el Juzgado 23 Penal Municipal con Funci\u00f3n de Control de Garant\u00edas de Bogot\u00e1. En expediente. Cuaderno 2. Disponible en CD. Documento: \u201cFALLO TUTELA 039-2020 DESPU\u00c9S DE NULIDAD.pdf\u201d. El 13 de agosto de 2021, la autoridad judicial remiti\u00f3 el expediente nuevamente para su revisi\u00f3n. \u00a0<\/p>\n<p>52 Oficio 120-TUT-52173 de 8 de octubre de 2021. En expediente. Documento remitido por correo electr\u00f3nico: \u201c52173 Ana Elvia Morales de Corredor RAD Expediente T-8.111.691.pdf\u201d. Folio 1.\u00a0 \u00a0<\/p>\n<p>53 En expediente. Documento remitido por correo electr\u00f3nico: \u201cana Elvia.pdf\u201d. Folios 41 (autorizaci\u00f3n del 3 de marzo de 2021), 48 (autorizaci\u00f3n del 3 de febrero de 2021); 54 (autorizaci\u00f3n del 7 de enero de 2021); 63 (autorizaci\u00f3n del 7 de diciembre de 2020); 68 (autorizaci\u00f3n del 9 de noviembre de 2020); 75 (autorizaci\u00f3n del 8 de octubre de 2020); 81 (autorizaci\u00f3n del 3 de septiembre de 2020); y, 90 (autorizaci\u00f3n del 9 de agosto de 2020).\u00a0 \u00a0<\/p>\n<p>54 En expediente electr\u00f3nico. Documento remitido por correo electr\u00f3nico: \u201cana Elvia.pdf\u201d. Folios 1 (autorizaci\u00f3n del 6 de octubre de 2021); 6 (autorizaci\u00f3n del 3 de septiembre de 2021); 10 (autorizaci\u00f3n del 4 de agosto de 2021); 25 (autorizaci\u00f3n del 2 de julio de 2021); 27 (autorizaci\u00f3n del 6 de mayo de 2021); y, 33 (autorizaci\u00f3n del 7 de abril de 2021). \u00a0 \u00a0<\/p>\n<p>55 En expediente. Documento: \u201cOficio OPT-A-2675 del 5 de octubre de 2021\u201d. Folio 1. \u00a0 \u00a0<\/p>\n<p>56 \u201cTERCERO. OFICIAR a la IPS Emanuel Instituto de Rehabilitaci\u00f3n y Habilitaci\u00f3n Infantil S.A.S para que, en el t\u00e9rmino de tres (3) d\u00edas siguientes a la notificaci\u00f3n del presente auto, comunique a este despacho si contin\u00faa a cargo de la atenci\u00f3n domiciliaria de la se\u00f1ora Ana Elvia Morales de Corredor. De ser as\u00ed, informe: (i) qu\u00e9 tratamiento m\u00e9dico ha otorgado a las patolog\u00edas de la se\u00f1ora Ana Elvia Morales de Corredor; y, (ii) en qu\u00e9 lugar atiende a la paciente. Asimismo, deber\u00e1 remitir los documentos que justifiquen sus respuestas\u201d.\u00a0 \u00a0<\/p>\n<p>57 Durante abril y mayo de 2020. Oficio 120-TUT-52173 del 25 de octubre de 2021. En expediente. Documento remitido por correo electr\u00f3nico: \u201c52173 Ana Elvia Morales de Corredor RAD Expediente T 8 111 691.pdf\u201d. Folios 5 y 6.\u00a0 \u00a0<\/p>\n<p>58 Desde el mes de junio de 2020, hasta el mes de febrero de 2021. Ibid. \u00a0<\/p>\n<p>59 Desde el mes de marzo de 2021, hasta el mes de septiembre de 2021. Ibid.\u00a0 \u00a0<\/p>\n<p>60 En expediente. Documento remitido por correo electr\u00f3nico: \u201cNotas de enfermer\u00eda.pdf\u201d. Folios de 1 a 101. \u00a0<\/p>\n<p>61 En expediente. Documento remitido por correo electr\u00f3nico: \u201cHistoria cl\u00ednica domiciliarios.pdf\u201d. Folios de 1 a 22. \u00a0<\/p>\n<p>62 En expediente. Documento remitido por correo electr\u00f3nico: \u201cHist\u00f3rico de entrega de medicamentos.csv\u201d. Libro \u201cHist\u00f3rico de entrega de medicam\u201d. \u00a0<\/p>\n<p>63 En expediente. Documento remitido por correo electr\u00f3nico: \u201cSERVICIOS AUTORIZADOS PACIENTE MORALES ANA ELVIA CC 20260470.csv\u201d. Libro \u201cPM ENVIADO\u201d.\u00a0 \u00a0<\/p>\n<p>64 Oficio 120-TUT-52173 del 26 de octubre de 2021. En expediente. Documento remitido por correo electr\u00f3nico: \u201c52173 Ana Elvia Morales de Corredor RAD Expediente T 8 111 691.pdf\u201d. Folios 5 y 6. \u00a0<\/p>\n<p>65 Seg\u00fan el escrito de la accionada y la historia cl\u00ednica, el profesional de la salud encargado orden\u00f3: 15 terapias respiratorias con vibropercusi\u00f3n para movilizaci\u00f3n de secreciones con succi\u00f3n en caso de requerirlo y con berodual, 15 terapias f\u00edsicas, 15 terapias de fonoaudiolog\u00eda, 15 terapias Ocupacionales, y dos sesiones de psicolog\u00eda. Oficio 120-TUT-52173 del 26 de octubre de 2021. En expediente. Documento remitido por correo electr\u00f3nico: \u201c52173 Ana Elvia Morales de Corredor RAD Expediente T 8 111 691.pdf\u201d. Folios 20 a 22. \u00a0<\/p>\n<p>66 Oficio 120-TUT-52173 del 26 de octubre de 2021. En expediente. Documento remitido por correo electr\u00f3nico: \u201c52173 Ana Elvia Morales de Corredor RAD Expediente T 8 111 691.pdf\u201d. Folios 5 y 6. \u00a0<\/p>\n<p>67 Ibid. \u00a0<\/p>\n<p>68 En expediente. Documento remitido por correo electr\u00f3nico: \u201cHistoria cl\u00ednica domiciliarios a\u00f1o 2020.pdf\u201d. Folios de 1 a 30 \u00a0<\/p>\n<p>69 En expediente. Documento remitido por correo electr\u00f3nico: \u201cHistoria Cl\u00ednica Cafam.pdf\u201d. Folios de 1 a 30 \u00a0<\/p>\n<p>70 En expediente. Documento: \u201cOficio OPT-A-2719 del 20 de octubre de 2021\u201d. Folio 1.\u00a0 \u00a0<\/p>\n<p>72 Ibid. Folios 26 a 18. \u00a0<\/p>\n<p>73 Este cap\u00edtulo fue desarrollado con fundamento en las consideraciones de la Sentencia T-338 de 2021, M.P. Gloria Stella Ortiz Delgado. \u00a0<\/p>\n<p>74 Decreto 2591 de 1991. Art\u00edculo 10. \u201cLa acci\u00f3n de tutela podr\u00e1 ser ejercida, en todo momento y lugar, por cualquiera persona vulnerada o amenazada en uno de sus derechos fundamentales, quien actuar\u00e1 por s\u00ed misma o a trav\u00e9s de representante. Los poderes se presumir\u00e1n aut\u00e9nticos. \/\/ Tambi\u00e9n se pueden agenciar derechos ajenos cuando el titular de los mismos no est\u00e9 en condiciones de promover su propia defensa. Cuando tal circunstancia ocurra, deber\u00e1 manifestarse en la solicitud. \/\/ Tambi\u00e9n podr\u00e1 ejercerla el Defensor del Pueblo y los personeros municipales\u201d.\u00a0 \u00a0<\/p>\n<p>75 De conformidad con los art\u00edculos 46 y siguientes del Decreto 2591 de 1991, el Defensor del Pueblo o los personeros municipales pueden interponer acciones de tutela para proteger los derechos fundamentales de terceros.\u00a0 \u00a0<\/p>\n<p>76 Decreto 2591 de 1991. Art\u00edculo 10. \u201cLa acci\u00f3n de tutela podr\u00e1 ser ejercida, en todo momento y lugar, por cualquiera persona vulnerada o amenazada en uno de sus derechos fundamentales, quien actuar\u00e1 por s\u00ed misma o a trav\u00e9s de representante. Los poderes se presumir\u00e1n aut\u00e9nticos. \/\/ Tambi\u00e9n se pueden agenciar derechos ajenos cuando el titular de los mismos no est\u00e9 en condiciones de promover su propia defensa. Cuando tal circunstancia ocurra, deber\u00e1 manifestarse en la solicitud. \/\/ Tambi\u00e9n podr\u00e1 ejercerla el Defensor del Pueblo y los personeros municipales\u201d. \u00a0<\/p>\n<p>77 Sentencia SU-150 de 2021, M.P. Alejandro Linares Cantillo. \u00a0<\/p>\n<p>78 Sentencia SU-508 de 2020, MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas. Reitera, entre otras, las sentencias T-014 de 2017, M.P. Gabriel Eduardo Mendoza Martelo; y, T-200 de 2016, M.P. Jorge Iv\u00e1n Palacio Palacio. \u00a0<\/p>\n<p>79 Sentencia SU-150 de 2021, M.P. Alejandro Linares Cantillo. \u00a0<\/p>\n<p>80 \u201cNo obstante, este Tribunal tambi\u00e9n ha rese\u00f1ado que, a pesar de que dicha ratificaci\u00f3n no es un requisito indispensable para facultar la actuaci\u00f3n del agente oficioso en materia de tutela, cuando ella se presenta, tal circunstancia convalida la gesti\u00f3n adelantada por el agente y, en consecuencia, le otorga legitimaci\u00f3n en la causa por activa\u201d. (Negrilla fuera del texto). Fundamento jur\u00eddico 40. Ibid.\u00a0 \u00a0<\/p>\n<p>81Seg\u00fan la historia cl\u00ednica aportada en sede de revisi\u00f3n, padece de demencia en la enfermedad de Alzheimer at\u00edpica o de tipo mixto, diabetes mellitus, osteoartrosis, hipertensi\u00f3n arterial, constipaci\u00f3n, incontinencia mixta, fractura de cadera bilateral, catarata en ojo izquierdo y presenta secuelas de enfermedad cardiovascular. Adicionalmente, es usuaria de ox\u00edgeno domiciliario y depende por completo de un tercero para desarrollar sus actividades diarias como ba\u00f1arse, alimentarse y vestirse. Valoraci\u00f3n m\u00e9dica del 7 de octubre de 2021. En expediente. Documento remitido por correo electr\u00f3nico: \u201cHistoria cl\u00ednica domiciliarios.pdf\u201d. Folios16 a 22. \u00a0<\/p>\n<p>82 En los t\u00e9rminos de los art\u00edculos 86 de la Constituci\u00f3n y 1\u00ba, 5\u00ba y 13 del Decreto 2591 de 1991. Sentencia T-188 de 2020, M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>83 Decreto 2591 de 1991. Art\u00edculo 42. Numeral 2: \u201cLa acci\u00f3n de tutela proceder\u00e1 contra acciones u omisiones de particulares en los siguientes casos: [\u2026] Cuando aqu\u00e9l contra quien se hubiere hecho la solicitud est\u00e9 encargado de la prestaci\u00f3n del servicio p\u00fablico de salud\u201d (Negrilla fuera del texto). \u00a0<\/p>\n<p>84 Sentencia SU-508 de 2020, MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas.\u00a0 \u00a0<\/p>\n<p>85 Art\u00edculo 86. \u201cToda persona tendr\u00e1 acci\u00f3n de tutela para reclamar ante los jueces, en todo momento y lugar, mediante un procedimiento preferente y sumario, por s\u00ed misma o por quien act\u00fae a su nombre, la protecci\u00f3n inmediata de sus derechos constitucionales fundamentales, cuando quiera que \u00e9stos resulten vulnerados o amenazados por la acci\u00f3n o la omisi\u00f3n de cualquier autoridad p\u00fablica. \/\/ La protecci\u00f3n consistir\u00e1 en una orden para que aquel respecto de quien se solicita la tutela, act\u00fae o se abstenga de hacerlo. El fallo, que ser\u00e1 de inmediato cumplimiento, podr\u00e1 impugnarse ante el juez competente y, en todo caso, \u00e9ste lo remitir\u00e1 a la Corte Constitucional para su eventual revisi\u00f3n. \/\/ Esta acci\u00f3n solo proceder\u00e1 cuando el afectado no disponga de otro medio de defensa judicial, salvo que aquella se utilice como mecanismo transitorio para evitar un perjuicio irremediable. \/\/ En ning\u00fan caso podr\u00e1n transcurrir m\u00e1s de diez d\u00edas entre la solicitud de tutela y su resoluci\u00f3n. \/\/ La ley establecer\u00e1 los casos en los que la acci\u00f3n de tutela procede contra particulares encargados de la prestaci\u00f3n de un servicio p\u00fablico o cuya conducta afecte grave y directamente el inter\u00e9s colectivo, o respecto de quienes el solicitante se halle en estado de subordinaci\u00f3n o indefensi\u00f3n\u201d.\u00a0 \u00a0<\/p>\n<p>86 Sentencia T-235 de 2018, M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>87 Derecho de petici\u00f3n Q-841962 del 13 de noviembre de 2019. En expediente. Cuaderno 1. Folios 29 y 30.\u00a0 \u00a0<\/p>\n<p>88 Respuesta de FAMISANAR E.P.S. a queja de radicado Q-841962. En expediente. Cuaderno 1. Folio 40.\u00a0 \u00a0<\/p>\n<p>89 Transcrito en escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folio 6. \u00a0<\/p>\n<p>90 Historia cl\u00ednica proferida por National Clinics Centenario S.A.S. En expediente. Cuaderno 1. Folios del 53 al 60.\u00a0 \u00a0<\/p>\n<p>91 Ver el inciso 4\u00ba del art\u00edculo 86 de la Constituci\u00f3n y del numeral 1\u00ba del art\u00edculo 6\u00ba del Decreto 2591 de 1991. \u00a0<\/p>\n<p>92 \u201cProcede como mecanismo definitivo cuando el medio ordinario dispuesto para resolver las controversias, no es id\u00f3neo y eficaz, conforme a las circunstancias del caso que se estudia\u201d. Sentencia T-188 de 2020, M.P. Gloria Stella Ortiz Delgado. Ver adem\u00e1s las sentencias T-800 de 2012, M.P. Jorge Iv\u00e1n Palacio Palacio; T-436 de 2005, M.P. Clara In\u00e9s Vargas; y T-108 de 2007, M.P. Rodrigo Escobar Gil. \u00a0<\/p>\n<p>93 Sobre el particular, la Corte ha establecido que \u201cel medio debe ser id\u00f3neo, lo que significa que debe ser materialmente apto para producir el efecto protector de los derechos fundamentales. Adem\u00e1s, debe ser un medio eficaz, esto es, que debe estar dise\u00f1ado de forma tal que brinde oportunamente una protecci\u00f3n al derecho\u201d. Sentencia T-040 de 2016, M.P. Alejandro Linares Cantillo. \u00a0<\/p>\n<p>94 Asimismo, el juez de tutela debe tener en cuenta que no puede suplantar al juez ordinario. Ver al respecto la Sentencia T-235 de 2018, M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>95\u201cProcede como mecanismo transitorio, cuando a pesar de la existencia de un medio ordinario de defensa, este no impide la ocurrencia de un perjuicio irremediable, conforme a la especial situaci\u00f3n del peticionario\u201d Sentencia T-188 de 2020, M.P. Gloria Stella Ortiz Delgado. Reitera las sentencias T-800 de 2012, M.P. Jorge Iv\u00e1n Palacio Palacio; y T-859 de 2004, M.P. Clara In\u00e9s Vargas. Seg\u00fan la jurisprudencia, y de acuerdo con la sentencia T-375 de 2018, dicha excepci\u00f3n al requisito de subsidiariedad exige que se verifique lo siguiente: \u201c(i) una afectaci\u00f3n inminente del derecho -elemento temporal respecto del da\u00f1o-; (ii) la urgencia de las medidas para remediar o prevenir el perjuicio irremediable; (iii) la gravedad del perjuicio -grado o impacto de la afectaci\u00f3n del derecho-; y (iv) el car\u00e1cter impostergable de las medidas para la efectiva protecci\u00f3n de las garant\u00edas fundamentales en riesgo\u201d. La protecci\u00f3n que puede ordenarse en este evento es temporal, tal y como lo dispone el art\u00edculo 10\u00ba del Decreto 2591 de 1991, el cual indica: \u201c[e]n el caso del inciso anterior, el juez se\u00f1alar\u00e1 expresamente en la sentencia que su orden permanecer\u00e1 vigente s\u00f3lo durante el t\u00e9rmino que la autoridad judicial competente utilice para decidir de fondo sobre la acci\u00f3n instaurada por el afectado\u201d. Entre otras, ver las sentencias T-225 de 1993, M.P. Vladimiro Naranjo Mesa; y\u00a0T-789 de 2003, M.P. Manuel Jos\u00e9 Cepeda Espinosa. \u00a0<\/p>\n<p>96 Ver al respecto las sentencias T-401 de 2017, M.P. Gloria Stella Ortiz Delgado; T-163 de 2017, M.P. Gloria Stella Ortiz Delgado; T-328 de 2011, M.P. Jorge Ignacio Pretelt Chaljub; T-456 de 2004, M.P. Jaime Araujo Renter\u00eda; T-789 de 2003, M.P. Manuel Jos\u00e9 Cepeda Espinosa; y T-136 de 2001, M.P. Rodrigo Uprimny Yepes, entre otras.\u00a0 \u00a0<\/p>\n<p>97 Sentencias T-662 de 2013, M.P. Luis Ernesto Vargas Silva; y T-527 de 2015, M.P. Gloria Stella Ortiz Delgado. \u00a0<\/p>\n<p>98 Para el efecto, la SNS adelantar\u00e1 un procedimiento informal, sumario y preferente. En primer lugar, tal como lo ha se\u00f1alado este Tribunal, ese proceso debe adelantarse con la menor formalidad posible. En ese sentido, no requiere de apoderado, ni la demanda exige formalidad alguna. Por otra parte, la entidad debe fallar el caso dentro de los 20 d\u00edas siguientes a la radicaci\u00f3n de la demanda. Esto significa que tiene un car\u00e1cter preferente y sumario. Adicionalmente, es un procedimiento que permite adoptar medidas cautelares, para proteger los derechos del accionante. Estas caracter\u00edsticas del proceso permiten advertir que la autoridad conoce y falla en derecho de manera definitiva como lo hace un juez. Ver al respecto las sentencias SU-124 de 2018, M.P. Gloria Stella Ortiz Delgado; y T-825 de 2012, M.P. Mauricio Gonz\u00e1lez Cuervo.\u00a0 \u00a0<\/p>\n<p>99 Sin importar si fueron incluidos expresamente o no.\u00a0 \u00a0<\/p>\n<p>100 Ley 1122 de 2007. Art\u00edculo 41. \u201cCon el fin de garantizar la efectiva prestaci\u00f3n del derecho a la salud de los usuarios del Sistema General de Seguridad Social en Salud y en ejercicio del art\u00edculo 116 de la Constituci\u00f3n Pol\u00edtica, la Superintendencia Nacional de Salud podr\u00e1 conocer y fallar en derecho, y con las facultades propias de un juez en los siguientes asuntos: \/\/ a) Cobertura de los servicios, tecnolog\u00edas en salud o procedimientos incluidos en el Plan de Beneficios en Salud (Plan Obligatorio de Salud), cuando su negativa por parte de las Entidades Promotoras de Salud o entidades que se les asimilen ponga en riesgo o amenace la salud del usuario, consultando la Constituci\u00f3n Pol\u00edtica y las normas que regulen la materia. [\u2026] \/\/ La funci\u00f3n jurisdiccional de la Superintendencia Nacional de Salud se desarrollar\u00e1 mediante un procedimiento sumario, con arreglo a los principios de publicidad, prevalencia del derecho sustancial, econom\u00eda, celeridad y eficacia, garantizando debidamente los derechos al debido proceso, defensa y contradicci\u00f3n. \/\/ La demanda debe ser dirigida a la Superintendencia Nacional de Salud, debe expresar con la mayor claridad las circunstancias de tiempo, modo y lugar; la pretensi\u00f3n, el derecho que se considere violado, as\u00ed como el nombre y direcci\u00f3n de notificaci\u00f3n del demandante y debe adjuntar los documentos que soporten los hechos. \/\/ La demanda podr\u00e1 ser presentada sin ninguna formalidad o autenticaci\u00f3n; por memorial, u otro medio de comunicaci\u00f3n escrito. No ser\u00e1 necesario actuar por medio de apoderado, esto sin perjuicio de las normas vigentes para la representaci\u00f3n y el derecho de postulaci\u00f3n. En el tr\u00e1mite del procedimiento jurisdiccional prevalecer\u00e1 la informalidad. \/\/ La Superintendencia Nacional de Salud emitir\u00e1 sentencia dentro de los siguientes t\u00e9rminos: \/\/ Dentro de los 20 d\u00edas siguientes a la radicaci\u00f3n de la demanda en los asuntos de competencia contenidos en los literales a), c), d) y e) del presente art\u00edculo. \/\/ [\u2026] \/\/ PAR\u00c1GRAFO 1o. Las providencias emitidas dentro del proceso jurisdiccional se notificar\u00e1n por el medio m\u00e1s \u00e1gil y efectivo. La sentencia podr\u00e1 ser apelada dentro de los 3 d\u00edas siguientes a su notificaci\u00f3n. En caso de ser concedido el recurso, el expediente deber\u00e1 ser remitido al Tribunal Superior del Distrito Judicial &#8211; Sala Laboral del domicilio del apelante. \/\/ PAR\u00c1GRAFO 2o. La Superintendencia Nacional de Salud solo podr\u00e1 conocer y fallar estos asuntos a petici\u00f3n de parte. No podr\u00e1 conocer de ning\u00fan asunto que por virtud de las disposiciones legales vigentes deba ser sometido al proceso de car\u00e1cter ejecutivo o acciones de car\u00e1cter penal. [\u2026]\u201d. (Negrillas fuera del texto). \u00a0 \u00a0<\/p>\n<p>101 M.P. Manuel Jos\u00e9 Cepeda Espinosa. \u00a0<\/p>\n<p>102 Inicialmente previsto en la Ley 1438 de 2011.\u00a0 \u00a0<\/p>\n<p>103 \u201cAudiencia P\u00fablica del 6 de diciembre de 2018. Ante la pregunta de la Magistrada Gloria Stella Ortiz sobre la capacidad de respuesta de la Superintendencia de Salud en sus funciones jurisdiccionales, el jefe de la entidad se\u00f1al\u00f3: \u2018en Colombia es imposible, Magistrada, hoy, hacer un fallo muchas veces en 10 d\u00edas de una actuaci\u00f3n que amerita hacer un debido proceso (\u2026) hoy no tenemos la infraestructura, la Superintendencia, para responder en los t\u00e9rminos que quieren todos los colombianos desde el \u00e1rea jurisdiccional, tenemos un retraso que puede estar en dos y tres a\u00f1os, por qu\u00e9 le menciono esto Magistrada, porque el 90% de los procesos que llegan a la Superintendencia al \u00e1rea jurisdiccional son econ\u00f3micos: licencias de paternidad, licencias de maternidad (\u2026)\u201d (extracto transcrito)\u201d. Sentencia T-423 de 2019, M.P. Gloria Stella Ortiz Delgado. Nota a pie de p\u00e1gina 41. \u00a0<\/p>\n<p>104 Ibidem.\u00a0 \u00a0<\/p>\n<p>105 Ley 1949 de 2019. Art\u00edculo 1. \u201cLa presente ley tiene por finalidad el fortalecimiento de la capacidad institucional de la Superintendencia Nacional de Salud en materia sancionatoria. \/\/ Adicionalmente se redefinen las competencias de la superintendencia, en materia de reintegro de recursos apropiados o reconocidos sin justa causa y en lo que respecta a la funci\u00f3n jurisdiccional y de conciliaci\u00f3n, modificando tambi\u00e9n en esta \u00faltima, los t\u00e9rminos procesales para decidir los asuntos de su conocimiento. \/\/ Finalmente, se adoptan medidas encaminadas a mitigar los efectos negativos de los procesos de reorganizaci\u00f3n en el flujo de recursos y pago de acreencias de las entidades que intervienen en estos, definiendo nuevas competencias en materia contable\u201d.\u00a0 \u00a0<\/p>\n<p>106 MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas.\u00a0 \u00a0<\/p>\n<p>107 A juicio de esta Corporaci\u00f3n, aunque la SNS profiri\u00f3 2.261 sentencias entre agosto de 2019 y junio de 2020, esto no permite concluir que la entidad super\u00f3 las dificultades se\u00f1aladas. Lo anterior, porque se desconoce cu\u00e1nto tiempo tard\u00f3 en adoptar esas decisiones. De modo que, mientras la situaci\u00f3n persista, el procedimiento sumario descrito no puede considerarse id\u00f3neo, ni eficaz para proteger los derechos fundamentales de los usuarios del Sistema General de Seguridad Social en Salud. Sentencia SU-508 de 2020, MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas.\u00a0 \u00a0<\/p>\n<p>108 Sentencia SU-074 de 2020, M.P. Gloria Stella Ortiz Delgado. \u00a0<\/p>\n<p>109 Sentencia SU-508 de 2020, MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas. Reitera las sentencias: T-025 de 2019, M.P. Alberto Rojas R\u00edos; T-527 de 2019, M.P. Jos\u00e9 Fernando Reyes Cuartas; y T-528 de 2019, M.P. Jos\u00e9 Fernando Reyes Cuartas; entre otras.\u00a0 \u00a0<\/p>\n<p>110 Es decir, no prev\u00e9 si se concede en el suspensivo o en el devolutivo.\u00a0 \u00a0<\/p>\n<p>111 Sentencia T-218 de 2018, M.P. Carlos Bernal Pulido.\u00a0 \u00a0<\/p>\n<p>112 Sentencia T-528 de 2019, M.P. Jos\u00e9 Fernando Reyes Cuartas. \u00a0<\/p>\n<p>113 Esta Corporaci\u00f3n ha se\u00f1alado que el C\u00f3digo General del Proceso es aplicable al tr\u00e1mite jurisdiccional ante la SNS. Por lo tanto, en esos casos, procede aplicar lo establecido en el art\u00edculo 57 de la norma mencionada. Ver al respecto la Sentencia T-061 de 2019, M.P. Alejandro Linares Cantillo. \u00a0<\/p>\n<p>114 Sentencia T-001 de 2021, M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>115 De conformidad con las cifras reportadas por el DANE, la expectativa de vida en Colombia para ambos sexos en el a\u00f1o 2020 era de 76 a\u00f1os. Esta proyecci\u00f3n vari\u00f3 significativamente para el a\u00f1o 2021. Seg\u00fan la entidad, para el 2021 la expectativa de vida para hombres es de 73,7 a\u00f1os, mientras que para mujeres es de 80 a\u00f1os. La accionante cuenta con 86 a\u00f1os. Es decir, que supera el promedio de expectativa de vida en Colombia. Departamento Administrativo Nacional de Estad\u00edstica (@DANE_Colombia). \u201cLa esperanza de vida al nacer, para 2021, es de 80 a\u00f1os para las mujeres y 73,7 a\u00f1os para los hombres en el total nacional. En las cabeceras, la esperanza de vida al nacer es mayor que en las zonas rurales\u201d #DANELecuenta bit.ly\/3nEGojP 12 de enero de 2021, [Tuit] https:\/\/twitter.com\/DANE_Colombia\/status\/1348991535417798656?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1348991540576870403%7Ctwgr%5E%7Ctwcon%5Es2_&amp;ref_url=https%3A%2F%2Fwww.eltiempo.com%2Feconomia%2Fsectores%2Fdane-revela-expectativa-de-vida-en-colombia-581272 [consulta 20 de octubre de 2021]. \u00a0<\/p>\n<p>116 Sentencia T-086 de 2015, M.P. Jorge Ignacio Pretelt Chaljub. \u00a0<\/p>\n<p>118 Sentencias T-056 de 1994, M.P. Eduardo Cifuentes Mu\u00f1oz; T-456 de 1994, M.P. Alejandro Mart\u00ednez Caballero; T-1116 de 2000, M.P. Alejandro Mart\u00ednez Caballero; T-849 de 2009, M.P. Jorge Ignacio Pretelt Chaljub; y T-300 de 2010, M.P. Jorge Ignacio Pretelt Chaljub.\u00a0 \u00a0<\/p>\n<p>119 Cap\u00edtulo elaborado con fundamento en las Sentencias T-338 de 2021 y SU-124 de 2018, M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>120 Constituci\u00f3n Pol\u00edtica. Art\u00edculo 49. \u201cLa atenci\u00f3n de la salud y el saneamiento ambiental son servicios p\u00fablicos a cargo del Estado. Se garantiza a todas las personas el acceso a los servicios de promoci\u00f3n, protecci\u00f3n y recuperaci\u00f3n de la salud. \/\/ Corresponde al Estado organizar, dirigir y reglamentar la prestaci\u00f3n de servicios de salud a los habitantes y de saneamiento ambiental conforme a los principios de eficiencia, universalidad y solidaridad. Tambi\u00e9n, establecer las pol\u00edticas para la prestaci\u00f3n de servicios de salud por entidades privadas, y ejercer su vigilancia y control. As\u00ed mismo, establecer las competencias de la Naci\u00f3n, las entidades territoriales y los particulares y determinar los aportes a su cargo en los t\u00e9rminos y condiciones se\u00f1alados en la ley. [\u2026]\u201d \u00a0<\/p>\n<p>121 Ver al respecto las sentencias T-859 de 2003, M.P. Eduardo Montealegre Lynett; T-837 de 2006, M.P Humberto Antonio Sierra Porto; T-631 de 2007, M.P Humberto Antonio Sierra Porto; T-076 de 2008, M.P Rodrigo Escobar Gil; T-760 de 2008, M.P. Manuel Jos\u00e9 Cepeda Espinosa, entre otras. \u00a0<\/p>\n<p>122 La calidad consiste en \u201cque los tratamientos, medicamentos, cirug\u00edas, procedimientos y dem\u00e1s prestaciones en salud requeridas contribuyan a la mejora de las condiciones de vida de los pacientes\u201d. As\u00ed mismo, la eficiencia \u201cimplica que los tr\u00e1mites administrativos a los que est\u00e1 sujeto el paciente sean razonables, no demoren excesivamente el acceso y no impongan al interesado una carga que no le corresponde asumir\u201d. Que sea oportuna hace referencia a que la persona \u201cdebe gozar de la prestaci\u00f3n del servicio en el momento que corresponde para recuperar su salud, sin sufrir mayores dolores y deterioros\u201d. Sentencia T-612 de 2014, M.P. Jorge Iv\u00e1n Palacio Palacio.\u00a0 \u00a0<\/p>\n<p>123 Sentencia SU-124 de 2018, M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>124 Ley Estatutaria 1751 de 2015. Art\u00edculo 2. \u201cNaturaleza y contenido del derecho fundamental a la salud. El derecho fundamental a la salud es aut\u00f3nomo e irrenunciable en lo individual y en lo colectivo. Comprende el acceso a los servicios de salud de manera oportuna, eficaz y con calidad para la preservaci\u00f3n, el mejoramiento y la promoci\u00f3n de la salud. El Estado adoptar\u00e1 pol\u00edticas para asegurar la igualdad de trato y oportunidades en el acceso a las actividades de promoci\u00f3n, prevenci\u00f3n, diagn\u00f3stico, tratamiento, rehabilitaci\u00f3n y paliaci\u00f3n para todas las personas. De conformidad con el art\u00edculo 49 de la Constituci\u00f3n Pol\u00edtica, su prestaci\u00f3n como servicio p\u00fablico esencial obligatorio, se ejecuta bajo la indelegable direcci\u00f3n, supervisi\u00f3n, organizaci\u00f3n, regulaci\u00f3n, coordinaci\u00f3n y control del Estado\u201d. \u00a0<\/p>\n<p>125 La jurisprudencia ha definido la salud como \u201cun derecho complejo, tanto por su concepci\u00f3n, como por la diversidad de obligaciones que de \u00e9l se derivan y por la magnitud y variedad de acciones y omisiones que su cumplimiento demanda del Estado y de la sociedad en general\u201d. Sentencia T-760 de 2008, M.P. Manuel Jos\u00e9 Cepeda Espinosa. Ver al respecto, entre otras, las sentencias T-539 de 2013, M.P. Jorge Ignacio Pretelt Chaljub; T-499 de 2014, M.P. Alberto Rojas R\u00edos; T-745 de 2014, M.P. Mauricio Gonz\u00e1lez Cuervo; C-313 de 2014, M.P. Gabriel Eduardo Mendoza Martelo; T-094 de 2016, M.P. Alejandro Linares Cantillo; y T-014 de 2017, M.P. Gabriel Eduardo Mendoza Martelo.\u00a0 \u00a0<\/p>\n<p>126 Ley 1751 de 2015. Art\u00edculo 8. \u201cLos servicios y tecnolog\u00edas de salud deber\u00e1n ser suministrados de manera completa para prevenir, paliar o curar la enfermedad, con independencia del origen de la enfermedad o condici\u00f3n de salud, del sistema de provisi\u00f3n, cubrimiento o financiaci\u00f3n definido por el legislador. No podr\u00e1 fragmentarse la responsabilidad en la prestaci\u00f3n de un servicio de salud espec\u00edfico en desmedro de la salud del usuario. \/\/ En los casos en los que exista duda sobre el alcance de un servicio o tecnolog\u00eda de salud cubierto por el Estado, se entender\u00e1 que este comprende todos los elementos esenciales para lograr su objetivo m\u00e9dico respecto de la necesidad espec\u00edfica de salud diagnosticada\u201d.\u00a0 \u00a0<\/p>\n<p>127 Sentencia T-760 de 2008, M.P. Manuel Jos\u00e9 Cepeda Espinosa. \u201cEl principio de integralidad ha sido postulado por la Corte Constitucional ante situaciones en las cuales los servicios de salud requeridos son fraccionados o separados, de tal forma que al interesado la entidad responsable solo le autoriza una parte de lo que deber\u00eda recibir para recuperar su salud y lo obliga a costearse por s\u00ed mismo la otra parte del servicio m\u00e9dico requerido. Esta situaci\u00f3n de fraccionamiento del servicio tiene diversas manifestaciones en raz\u00f3n al inter\u00e9s que tiene la entidad responsable en eludir un costo que a su juicio no le corresponde asumir.\u201d \u00a0<\/p>\n<p>128 M.P. Gabriel Eduardo Mendoza Martelo.\u00a0 \u00a0<\/p>\n<p>129 Sentencia T-402 de 2018, M.P. Diana Fajardo Rivera.\u00a0 \u00a0<\/p>\n<p>130 M.P. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas. \u00a0<\/p>\n<p>131 Al respecto, la Sentencia SU-508 de 2020, MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas, se\u00f1al\u00f3 que esa protecci\u00f3n especial est\u00e1 reconocida por el par\u00e1grafo del Art\u00edculo 6 de la Ley 1751 de 2015, seg\u00fan el cual: \u201c[l]os principios enunciados en este art\u00edculo se deber\u00e1n interpretar de manera arm\u00f3nica sin privilegiar alguno de ellos sobre los dem\u00e1s. Lo anterior no obsta para que sean adoptadas acciones afirmativas en beneficio de sujetos de especial protecci\u00f3n constitucional como la promoci\u00f3n del inter\u00e9s superior de las ni\u00f1as, ni\u00f1os y mujeres en estado de embarazo y personas de escasos recursos, grupos vulnerables y sujetos de especial protecci\u00f3n\u201d. \u00a0<\/p>\n<p>132 Ver al respecto sentencias T-252 de 2017, M.P. Iv\u00e1n Escrucer\u00eda Mayolo; y T-339 de 2017, M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>133 Ibid.\u00a0 \u00a0<\/p>\n<p>134 \u201cEl derecho al disfrute del m\u00e1s alto nivel posible de salud\u201d. P\u00e1rrafo 25: \u201cEn lo que se refiere al ejercicio del derecho a la salud de las personas mayores, el Comit\u00e9, conforme a lo dispuesto en los p\u00e1rrafos 34 y 35 de la observaci\u00f3n general N\u00ba 6 (1995), reafirma la importancia de un enfoque integrado de la salud que abarque la prevenci\u00f3n, la curaci\u00f3n y la rehabilitaci\u00f3n. Esas medidas deben basarse en reconocimientos peri\u00f3dicos para ambos sexos; medidas de rehabilitaci\u00f3n f\u00edsica y psicol\u00f3gica destinadas a mantener la funcionalidad y la autonom\u00eda de las personas mayores; y la prestaci\u00f3n de atenciones y cuidados a los enfermos cr\u00f3nicos y en fase terminal, ahorr\u00e1ndoles dolores evitables y permiti\u00e9ndoles morir con dignidad\u201d. Comit\u00e9 de Derechos Econ\u00f3micos, Sociales y Culturales. Observaci\u00f3n General 14. El derecho al disfrute del m\u00e1s alto nivel posible de salud. 11\/08\/2000. E\/C.12\/2000\/4. Disponible en: https:\/\/www.acnur.org\/fileadmin\/Documentos\/BDL\/2001\/1451.pdf. Consultado el 20 de septiembre de 2021.\u00a0 \u00a0<\/p>\n<p>135 Sentencia T-471 de 2018, M.P. Alberto Rojas R\u00edos. \u00a0<\/p>\n<p>136 Ibid. \u00a0<\/p>\n<p>137 Sentencia T-014 de 2017, M.P. Gabriel Eduardo Mendoza Martelo. \u00a0<\/p>\n<p>138 M.P. Diana Fajardo Rivera.\u00a0 \u00a0<\/p>\n<p>139 \u201cLa Corte ha dispuesto que la prestaci\u00f3n de los servicios de salud que requieran debe garantizarse de forma continua, permanente y eficiente como consecuencia de la cl\u00e1usula de Estado social de derecho consagrada en la Constituci\u00f3n. Esta Corporaci\u00f3n ha planteado esta obligaci\u00f3n en la medida que las personas de esta poblaci\u00f3n \u2018tienen derecho a una protecci\u00f3n reforzada en salud, en atenci\u00f3n a su condici\u00f3n de debilidad manifiesta y por el hecho de ostentar -desde el punto de vista constitucional- el rol de sujeto privilegiado\u2019. La Corte ha basado tal interpretaci\u00f3n en el Art\u00edculo 46 de la Constituci\u00f3n, de conformidad con el cual \u2018[e]l Estado, la sociedad y la familia concurrir\u00e1n para la protecci\u00f3n y la asistencia de las personas de la tercera edad y promover\u00e1n su integraci\u00f3n a la vida activa y comunitaria.\u2019 Agrega dicha norma que \u2018[e]l Estado les garantizar\u00e1 los servicios de la seguridad social integral y el subsidio alimentario en caso de indigencia.\u2019\u201d Sentencia T-122 de 2021, M.P. Diana Fajardo Rivera. Reiter\u00f3 las sentencias T-057 de 2013, M.P. (e) Alexei Julio Estrada; T-296 de 2016, M.P. Alejandro Linares Cantillo; T-405 de 2017, M.P. Iv\u00e1n Escrucer\u00eda Mayolo; T-491 de 2018, M.P. Diana Fajardo Rivera; SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos; entre otras. \u00a0<\/p>\n<p>140 Constituci\u00f3n. Art\u00edculo 46. \u201cEl Estado, la sociedad y la familia concurrir\u00e1n para la protecci\u00f3n y la asistencia de las personas de la tercera edad y promover\u00e1n su integraci\u00f3n a la vida activa y comunitaria. \/\/ El Estado les garantizar\u00e1 los servicios de la seguridad social integral y el subsidio alimentario en caso de indigencia\u201d.\u00a0 \u00a0<\/p>\n<p>141 Ley 1751 de 2015. Art\u00edculo 11. \u201cLa atenci\u00f3n de ni\u00f1os, ni\u00f1as y adolescentes, mujeres en estado de embarazo, desplazados, v\u00edctimas de violencia y del conflicto armado, la poblaci\u00f3n adulta mayor, personas que sufren de enfermedades hu\u00e9rfanas y personas en condici\u00f3n de discapacidad, gozar\u00e1n de especial protecci\u00f3n por parte del Estado. Su atenci\u00f3n en salud no estar\u00e1 limitada por ning\u00fan tipo de restricci\u00f3n administrativa o econ\u00f3mica. Las instituciones que hagan parte del sector salud deber\u00e1n definir procesos de atenci\u00f3n intersectoriales e interdisciplinarios que le garanticen las mejores condiciones de atenci\u00f3n. \/\/ [\u2026]\u201d.\u00a0 \u00a0<\/p>\n<p>142 Sentencias T-513 de 2020, T-275 de 2020 ambas con ponencia del Magistrado Jos\u00e9 Fernando Reyes Cuartas y T-259 de 2019 M.P. Antonio Jos\u00e9 Lizarazo Ocampo. \u00a0<\/p>\n<p>143 Sentencia T-513 de 2020 y T-275 de 2020, M.P. Jos\u00e9 Fernando Reyes Cuartas \u00a0<\/p>\n<p>144 Sentencias SU- 508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos; T-513 de 2020 y T-275 de 2020, M.P. Jos\u00e9 Fernando Reyes Cuartas.\u00a0 \u00a0<\/p>\n<p>145 Sentencia T-081 de 2019, M.P. Luis Guillermo Guerrero P\u00e9rez.\u00a0 \u00a0<\/p>\n<p>146 Este ac\u00e1pite tiene fundamento en las consideraciones expuestas en la Sentencia T-001 de 2021, M.P. Gloria Stella Ortiz Delgado. \u00a0<\/p>\n<p>147 Ver al respecto: Sentencias T-001 de 2021, M.P. Gloria Stella Ortiz Delgado; y, SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>148 Es decir, establecer, con el m\u00e1ximo grado de certeza permitido por la ciencia y la tecnolog\u00eda, cu\u00e1l es el tratamiento que mejor garantiza el derecho del paciente a acceder al m\u00e1s alto nivel de salud posible. Ver al respecto: Sentencias SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos; y, T-710 de 2017, M.P. Alejandro Linares Cantillo.\u00a0 \u00a0<\/p>\n<p>149 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>150 Ver al respecto: Sentencias T-027 de 2015 M.P. Luis Guillermo Guerrero P\u00e9rez, T-248 de 2016 M.P. Gabriel Eduardo Mendoza Martelo, T-036 de 2017 M.P. Alejandro Linares Cantillo, T-445 de 2017 M.P. Luis Guillermo Guerrero P\u00e9rez, T-061 de 2019 M.P. Alejandro Linares Cantillo, T-259 de 2019 M.P. Antonio Jos\u00e9 Lizarazo Ocampo, T-365 de 2019 M.P. Carlos Bernal Pulido; T-508 de 2019 M.P. Jos\u00e9 Fernando Reyes Cuartas; SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos; y, T-001 de 2021, M.P. Gloria Stella Ortiz Delgado; entre otras.\u00a0 \u00a0<\/p>\n<p>151 Ver al respecto: Sentencia T-710 de 2017, M.P. Alejandro Linares Cantillo; y, T-274 de 2009, M.P. Humberto Sierra Porto. \u00a0<\/p>\n<p>152 Sentencia T-710 de 2017, M.P. Alejandro Linares Cantillo. Reiter\u00f3 la Sentencia T-274 de 2009, M.P. Humberto Sierra Porto. \u00a0<\/p>\n<p>153 Ver al respecto: Sentencia T-710 de 2017, M.P. Alejandro Linares Cantillo; y, T-274 de 2009, M.P. Humberto Sierra Porto. \u00a0<\/p>\n<p>154 Ver al respecto: Sentencias T-001 de 2021, M.P. Gloria Stella Ortiz Delgado; y, SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>155 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos. \u00a0<\/p>\n<p>156 Ley 1751 de 2015. Art\u00edculo 15. \u201cEl Sistema garantizar\u00e1 el derecho fundamental a la salud a trav\u00e9s de la prestaci\u00f3n de servicios y tecnolog\u00edas, estructurados sobre una concepci\u00f3n integral de la salud, que incluya su promoci\u00f3n, la prevenci\u00f3n, la paliaci\u00f3n, la atenci\u00f3n de la enfermedad y rehabilitaci\u00f3n de sus secuelas. \/\/ En todo caso, los recursos p\u00fablicos asignados a la salud no podr\u00e1n destinarse a financiar servicios y tecnolog\u00edas en los que se advierta alguno de los siguientes criterios:\/\/ a) Que tengan como finalidad principal un prop\u00f3sito cosm\u00e9tico o suntuario no relacionado con la recuperaci\u00f3n o mantenimiento de la capacidad funcional o vital de las personas; \/\/ b) Que no exista evidencia cient\u00edfica sobre su seguridad y eficacia cl\u00ednica; \/\/ c) Que no exista evidencia cient\u00edfica sobre su efectividad cl\u00ednica; \/\/ d) Que su uso no haya sido autorizado por la autoridad competente; \/\/ e) Que se encuentren en fase de experimentaci\u00f3n; \/\/ f) Que tengan que ser prestados en el exterior. \/\/ Los servicios o tecnolog\u00edas que cumplan con esos criterios ser\u00e1n expl\u00edcitamente excluidos por el Ministerio de Salud y Protecci\u00f3n Social o la autoridad competente que determine la ley ordinaria, previo un procedimiento t\u00e9cnico-cient\u00edfico, de car\u00e1cter p\u00fablico, colectivo, participativo y transparente. [\u2026]\u201d.\u00a0 \u00a0<\/p>\n<p>157 Actualmente, los servicios y tecnolog\u00edas en salud que se encuentran incluidos en el PBS se garantizan mediante dos mecanismos de protecci\u00f3n: el de protecci\u00f3n colectiva regulado en la Resoluci\u00f3n 2481 de 2020 y el de protecci\u00f3n individual, reglamentado mediante las resoluciones 1885 y 2438 de 2018 y sus normas modificatorias.\u00a0 \u00a0<\/p>\n<p>158 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos. \u00a0<\/p>\n<p>159 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos. \u00a0<\/p>\n<p>161 En Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos, la Sala Plena tuvo en cuenta los conceptos emitidos por las universidades intervinientes en el proceso, Andes, Nacional de Colombia, de la Sabana, del Bosque y de Antioquia para efectos de establecer la importancia de suministrar algunos insumos que no curan los padecimientos de los pacientes. Se\u00f1al\u00f3 que, dejar de emplear algunos elementos, como los pa\u00f1itos h\u00famedos y la crema anti-escaras, en usuarios que no pueden realizar sus necesidades fisiol\u00f3gicas de manera aut\u00f3noma, puede causar dermatitis asociada a la incontinencia (DAI), lesiones de la piel con p\u00e9rdida progresiva de la misma, infecciones urinarias y lesiones cr\u00f3nicas que conducen a infecciones cut\u00e1neas. Respecto de estas \u00faltimas, precis\u00f3 que su falta de atenci\u00f3n oportuna y adecuada, en casos extremos, puede llevar a la sepsis, e incluso a la muerte \u00a0<\/p>\n<p>162 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos. \u00a0<\/p>\n<p>163 Consideraciones elaboradas con fundamento en la Sentencia T-338 de 2021, M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>164 Sentencia SU-508 de 2020, MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas.\u00a0 \u00a0<\/p>\n<p>165 Sentencia T-471 de 2018, M.P. Alberto Rojas R\u00edos. \u00a0<\/p>\n<p>166 Sentencia SU-508 de 2020, MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas.\u00a0 \u00a0<\/p>\n<p>167 Los servicios y tecnolog\u00edas excluidas del PBS est\u00e1n regulados en la Resoluci\u00f3n 244 de 2019 \u201cPor la cual se adopta el listado de servicios y tecnolog\u00edas que ser\u00e1n excluidas de la financiaci\u00f3n con recursos p\u00fablicos asignados a la salud\u201d.\u00a0 \u00a0<\/p>\n<p>168 Ver al respecto las sentencias T-171 de 2018, M.P. Cristina Pardo Schlesinger; T-464 de 2018, M.P. Diana Fajardo Rivera; T 239 de 2019, M.P. Alberto Rojas R\u00edos; T-485 de 2019, M.P. Alberto Rojas R\u00edos; T-224 de 2020, M.P. Diana Fajardo Rivera; y SU-508 de 2020, MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas. La jurisprudencia de esta Corporaci\u00f3n se\u00f1al\u00f3 que no fueron excluidas del PBS en la Resoluci\u00f3n 5267 de 2017, ni en la posterior actualizaci\u00f3n del sistema de exclusiones contenida en la Resoluci\u00f3n 244 de 2019.\u00a0 \u00a0<\/p>\n<p>169 Resoluci\u00f3n 2481 de 2020. \u201cPor la cual se actualizan los servicios y tecnolog\u00edas de salud financiados con recursos de la Unidad de Pago por Capitaci\u00f3n (UPC)\u201d. Art\u00edculo 60: \u201cAyudas t\u00e9cnicas. Los servicios y tecnolog\u00edas de salud financiados con recursos de la UPC incluyen las siguientes ayudas t\u00e9cnicas: [\u2026] Par\u00e1grafo 1. Est\u00e1n financiados con recursos de la UPC las siguientes estructuras de soporte para caminar: muletas, caminadores y bastones, las cuales se dar\u00e1n en calidad de pr\u00e9stamo, en los casos en que aplique (incluye entrenamiento de uso), con compromiso de devolverlos en buen estado, salvo el deterioro normal. En caso contrario, deber\u00e1n restituirse en dinero a su valor comercial. Par\u00e1grafo 2. No se financian con cargo a la UPC sillas de ruedas, plantillas y zapatos ortop\u00e9dicos\u201d. (Negrilla fuera del texto). Esta disposici\u00f3n reproduce el mismo contenido normativo de las Resoluciones 3512 de 2019, aplicada en la Sentencia SU-508 de 2020 y 5267 de 2017, aplicada a los casos estudiados en las Sentencias T-171 de 2018, M.P. Cristina Pardo Schlesinger y T-464 de 2018, M.P. Diana Fajardo Rivera.\u00a0 \u00a0<\/p>\n<p>170 \u201cPor la cual se establece el procedimiento de acceso, reporte de prescripci\u00f3n, suministro, verificaci\u00f3n, control, pago y an\u00e1lisis de la informaci\u00f3n de tecnolog\u00edas en salud no financiadas con recursos de la UPC, de servicios complementarios y se dictan otras disposiciones\u201d.\u00a0 \u00a0<\/p>\n<p>171 MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>172 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos. Al respecto, la Sala Plena tuvo en cuenta lo establecido en: Gonz\u00e1lez-Consuegra, Renata V.; Cardona-Mazo, Diana M.; Murcia-Trujillo, Paola A.; Matiz-Vera, Gustavo, Prevalencia de \u00falceras por presi\u00f3n en Colombia: informe preliminar, en Rev. Fac. Med., Vol. 62, No. 3, 2014, p. 373. \u00a0<\/p>\n<p>173 Sentencia SU-508 de 2020, MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas. \u00a0<\/p>\n<p>174 Ibid. \u00a0<\/p>\n<p>175 Numeral 18 del Anexo T\u00e9cnico de Resoluci\u00f3n 244 de 31 de enero de 2019, \u201cPor la cual se adopta el listado de servicios y tecnolog\u00edas que ser\u00e1n excluidas de la financiaci\u00f3n con recursos p\u00fablicos asignados a la salud\u201d. \u00a0<\/p>\n<p>176 Numeral 35 del Anexo T\u00e9cnico de Resoluci\u00f3n 244 de 31 de enero de 2019, \u201cPor la cual se adopta el listado de servicios y tecnolog\u00edas que ser\u00e1n excluidas de la financiaci\u00f3n con recursos p\u00fablicos asignados a la salud\u201d. \u00a0<\/p>\n<p>177 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>178 Ibid. En ese sentido, precis\u00f3 que las emulsiones son una composici\u00f3n de dos fases l\u00edquidas que no se mezclan. Esos elementos suelen utilizarse en productos cosm\u00e9ticos. De igual forma, que \u201cla crema se diferencia de la loci\u00f3n, en la medida en que \u00e9sta contiene un porcentaje mayor de agua que de aceite\u201d. \u00a0<\/p>\n<p>179 M.P. Gabriel Eduardo Mendoza Martelo.\u00a0 \u00a0<\/p>\n<p>180 Sentencia C-313 de 2014, M.P. Gabriel Eduardo Mendoza Martelo. \u00a0<\/p>\n<p>181 Ibid. \u00a0<\/p>\n<p>182 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>183 \u201cLa dermatitis irritativa por pa\u00f1al (DPi) es una enfermedad de etiolog\u00eda multifactorial, caracterizada por inflamaci\u00f3n en el \u00e1rea cubierta por el pa\u00f1al. [\u2026] En la patog\u00e9nesis de la DPi intervienen diversos elementos primariamente irritativos. El exceso de la humedad en el \u00e1rea, condicionada por el efecto oclusivo del pa\u00f1al, genera un aumento en el coeficiente de fricci\u00f3n y en el pH cut\u00e1neo, que da como resultado una disrupci\u00f3n local de la funci\u00f3n de la barrera cut\u00e1nea. Ante la modificaci\u00f3n del pH, las enzimas fecales atacan la piel incrementando el da\u00f1o. La barrera da\u00f1ada localmente es susceptible a una variedad de da\u00f1os biol\u00f3gicos, qu\u00edmicos y f\u00edsicos, que pueden causar o agravar la DPi. Entre \u00e9stos se incluyen el ataque de la piel por las enzimas fecales y otros irritantes presentes en la orina y las heces, la abrasi\u00f3n mec\u00e1nica y una mayor permeaci\u00f3n de irritantes qu\u00edmicos y otros microorganismos\u201d. SAEZ-DE-OCARIZ, M; OROZCO-COVARRUBIAS, L y GREENAWALT-RODRIGUEZ, S. \u201cAbordaje cl\u00ednico y manejo integral de la dermatitis irritativa por pa\u00f1al\u201d. Acta pediatr. M\u00e9x [online]. 2017, vol.38, n.6 [consultado el 27 de octubre de 2021], pp.427-432. Disponible en: &lt;http:\/\/www.scielo.org.mx\/scielo.php?script=sci_arttext&amp;pid=S0186-23912017000600427&amp;lng=es&amp;nrm=iso&gt;. ISSN 2395-8235. \u00a0https:\/\/doi.org\/10.18233\/apm38no6pp427-4321510. \u00a0<\/p>\n<p>184 Ibid. P\u00e1g. 430.\u00a0 \u00a0<\/p>\n<p>185 Numeral 18 del Anexo T\u00e9cnico de Resoluci\u00f3n 244 de 31 de enero de 2019, \u201cPor la cual se adopta el listado de servicios y tecnolog\u00edas que ser\u00e1n excluidas de la financiaci\u00f3n con recursos p\u00fablicos asignados a la salud\u201d. \u00a0<\/p>\n<p>186 Numeral 35 del Anexo T\u00e9cnico de Resoluci\u00f3n 244 de 31 de enero de 2019, \u201cPor la cual se adopta el listado de servicios y tecnolog\u00edas que ser\u00e1n excluidas de la financiaci\u00f3n con recursos p\u00fablicos asignados a la salud\u201d. \u00a0<\/p>\n<p>187 Este principio activo fue incluido en el PBS expresamente en los numerales 329 y 330 del Anexo N\u00b0 1 \u201cListado de medicamentos financiados con recursos de la UPC\u201d de la Resoluci\u00f3n 3512 de 2019, \u201cPor la cual se actualizan los servicios y tecnolog\u00edas de salud financiados con recursos de la Unidad de Pago por Capitaci\u00f3n (UPC)\u201d. Esa norma estaba vigente al momento de interponer la acci\u00f3n de tutela. Por tanto, es la norma aplicable al caso concreto. En todo caso, ese insumo tambi\u00e9n fue incluido en la regulaci\u00f3n actual del PBS. Puntualmente, se encuentra en los numerales 356 y 357 del Anexo N\u00b0 1 \u201cListado de medicamentos financiados con recursos de la UPC\u201d de la Resoluci\u00f3n 2481 de 2020, \u201cPor la cual se actualizan los servicios y tecnolog\u00edas de salud financiados con recursos de la Unidad de Pago por Capitaci\u00f3n (UPC)\u201d.\u00a0 \u00a0<\/p>\n<p>188 Este principio activo fue incluido en el PBS expresamente en el numeral 102 del Anexo N\u00b0 1 \u201cListado de medicamentos financiados con recursos de la UPC\u201d de la Resoluci\u00f3n 3512 de 2019, \u201cPor la cual se actualizan los servicios y tecnolog\u00edas de salud financiados con recursos de la Unidad de Pago por Capitaci\u00f3n (UPC)\u201d. Esa norma estaba vigente al momento de interponer la acci\u00f3n de tutela. Por tanto, es la norma aplicable al caso concreto. En todo caso, ese insumo tambi\u00e9n fue incluido en la regulaci\u00f3n actual del PBS. Puntualmente, se encuentra en el numeral 119 del Anexo N\u00b0 1 \u201cListado de medicamentos financiados con recursos de la UPC\u201d de la Resoluci\u00f3n 2481 de 2020, \u201cPor la cual se actualizan los servicios y tecnolog\u00edas de salud financiados con recursos de la Unidad de Pago por Capitaci\u00f3n (UPC)\u201d. \u00a0<\/p>\n<p>189 M.P. Jos\u00e9 Fernando Reyes Cuartas.\u00a0 \u00a0<\/p>\n<p>190 \u201cPor la cual se adopta el listado de servicios y tecnolog\u00edas que ser\u00e1n excluidas de la financiaci\u00f3n con recursos p\u00fablicos asignados a la salud\u201d.\u00a0 \u00a0<\/p>\n<p>191 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos. \u00a0<\/p>\n<p>192 Ver al respecto: Sentencias SU-508 de 2020, MM. PP Jos\u00e9 Fernando Reyes Cuartas; T-475 de 2020, M.P. Alejandro Linares Cantillo; y, T-409 de 2019, M.P. Gloria Stella Ortiz Delgado.\u00a0 \u00a0<\/p>\n<p>193 Ley 1751 de 2015. Art\u00edculo 6. Literal C. \u201cEl derecho fundamental a la salud incluye los siguientes elementos esenciales e interrelacionados: [\u2026] c) Accesibilidad. Los servicios y tecnolog\u00edas de salud deben ser accesibles a todos, en condiciones de igualdad, dentro del respeto a las especificidades de los diversos grupos vulnerables y al pluralismo cultural. La accesibilidad comprende la no discriminaci\u00f3n, la accesibilidad f\u00edsica, la asequibilidad econ\u00f3mica y el acceso a la informaci\u00f3n\u201d. \u00a0<\/p>\n<p>194 Ver al respecto: Sentencias SU-508 de 2020, MM. PP Jos\u00e9 Fernando Reyes Cuartas y T-409 de 2019, M.P. Gloria Stella Ortiz Delgado. \u00a0<\/p>\n<p>195 As\u00ed lo establec\u00eda el art\u00edculo 121 de la Resoluci\u00f3n 3512 de 2019, norma aplicable al momento de la presentaci\u00f3n de la acci\u00f3n de tutela. En todo caso, el contenido de esa disposici\u00f3n fue replicado en el art\u00edculo 121 de la Resoluci\u00f3n 2481 de 2020, \u201cPor la cual se actualizan integralmente los servicios y tecnolog\u00edas de salud financiados con recursos de la Unidad de Pago por Capitaci\u00f3n (UPC)\u201d, as\u00ed: \u201cLos servicios y tecnolog\u00edas de salud financiados con recursos de la UPC, incluyen el traslado acu\u00e1tico, a\u00e9reo y terrestre (en ambulancia b\u00e1sica o medicalizada), en los siguientes casos: \/\/ 1. Movilizaci\u00f3n de pacientes con patolog\u00eda de urgencias, desde el sitio de ocurrencia de la misma, hasta una instituci\u00f3n hospitalaria, incluyendo el servicio prehospitalario y de apoyo terap\u00e9utico en ambulancia. \/\/ 2. Entre IPS dentro del territorio nacional de los pacientes remitidos, teniendo en cuenta las limitaciones en la oferta de servicios de la instituci\u00f3n en donde est\u00e1n siendo atendidos, que requieran de atenci\u00f3n en un servicio no disponible en la instituci\u00f3n remisora. Igualmente, para estos casos, est\u00e1 financiado con recursos de la UPC el traslado en ambulancia en caso de contrarreferencia. \/\/ El servicio de traslado cubrir\u00e1 el medio de transporte disponible en el sitio geogr\u00e1fico donde se encuentre el paciente, con base en su estado de salud, el concepto del m\u00e9dico tratante y el destino de la remisi\u00f3n, de conformidad con la normatividad vigente. \/\/ Asimismo, se financia el traslado en ambulancia del paciente remitido para atenci\u00f3n domiciliaria, si el m\u00e9dico as\u00ed lo prescribe\u201d. (Negrilla fuera del texto). \u00a0 \u00a0<\/p>\n<p>196 As\u00ed lo establec\u00eda el art\u00edculo 122 de la Resoluci\u00f3n 3512 de 2019, norma aplicada a los casos estudiados en la Sentencia SU-508 de 2020, MM. PP Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos. Esa norma resulta aplicable al caso concreto. Lo anterior, porque estaba vigente al momento de la presentaci\u00f3n de la acci\u00f3n de tutela. En todo caso, el contenido de esa disposici\u00f3n fue replicado en la regulaci\u00f3n actual del PBS. En concreto, el art\u00edculo 122 de la Resoluci\u00f3n 2481 de 2020, \u201cPor la cual se actualizan integralmente los servicios y tecnolog\u00edas de salud financiados con recursos de la Unidad de Pago por Capitaci\u00f3n (UPC)\u201d, establece: \u201cEl servicio de transporte en un medio diferente a la ambulancia para acceder a una atenci\u00f3n financiada con recursos de la UPC, no disponible en el lugar de residencia del afiliado, ser\u00e1 financiado en los municipios o corregimientos con la prima adicional para zona especial por dispersi\u00f3n geogr\u00e1fica. \/\/ Par\u00e1grafo. Las EPS o las entidades que hagan sus veces igualmente deber\u00e1n pagar el transporte del paciente ambulatorio cuando el usuario deba trasladarse a un municipio distinto al de su residencia para recibir los servicios mencionados en el art\u00edculo 10 de este acto administrativo o cuando existiendo estos en su municipio de residencia, la EPS o la entidad que llaga sus veces no los hubiere tenido en cuenta para la conformaci\u00f3n de su red de servicios. Esto aplica independientemente de si en el municipio la EPS o la entidad que haga sus veces recibe o no una UPC diferencial\u201d. \u00a0<\/p>\n<p>197 Respecto del transporte intermunicipal para paciente ambulatorio, la Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos, consider\u00f3 que est\u00e1 expresamente incluido en el PBS. En ese sentido, estableci\u00f3 que para el suministro de transporte en esos eventos deben tenerse en cuenta las siguientes reglas: (i) los costos de ese servicio ser\u00e1n financiados por la prima adicional por dispersi\u00f3n geogr\u00e1fica en las \u00e1reas que cuenten con ese rubro. En los dem\u00e1s eventos, ser\u00e1n financiados con cargo a la UPC; (iii) el requisito de la incapacidad econ\u00f3mica no ser\u00e1 exigible al paciente. Lo anterior, porque se trata de un servicio incluido en el PBS; (iv) la prestaci\u00f3n de este servicio no requiere prescripci\u00f3n m\u00e9dica debido al funcionamiento propio del sistema. La obligaci\u00f3n surge desde que se autoriza la prestaci\u00f3n del servicio en un municipio diferente; y, (v) estas reglas no aplican para la atenci\u00f3n de las tecnolog\u00edas excluidas del PBS. \u00a0<\/p>\n<p>198 Definici\u00f3n contenida en la Sentencia T-491 de 2018, M.P. Diana Fajardo Rivera.\u00a0 \u00a0<\/p>\n<p>199 As\u00ed lo establec\u00eda el art\u00edculo 121 de la Resoluci\u00f3n 3512 de 2019, norma aplicable al momento de la presentaci\u00f3n de la acci\u00f3n de tutela. En todo caso, el contenido de esa disposici\u00f3n fue replicado en el art\u00edculo 121 de la Resoluci\u00f3n 2481 de 2020, \u201cPor la cual se actualizan integralmente los servicios y tecnolog\u00edas de salud financiados con recursos de la Unidad de Pago por Capitaci\u00f3n (UPC)\u201d, as\u00ed: \u201cLos servicios y tecnolog\u00edas de salud financiados con recursos de la UPC, incluyen el traslado acu\u00e1tico, a\u00e9reo y terrestre (en ambulancia b\u00e1sica o medicalizada), en los siguientes casos: \/\/ 1. Movilizaci\u00f3n de pacientes con patolog\u00eda de urgencias, desde el sitio de ocurrencia de la misma, hasta una instituci\u00f3n hospitalaria, incluyendo el servicio prehospitalario y de apoyo terap\u00e9utico en ambulancia. \/\/ 2. Entre IPS dentro del territorio nacional de los pacientes remitidos, teniendo en cuenta las limitaciones en la oferta de servicios de la instituci\u00f3n en donde est\u00e1n siendo atendidos, que requieran de atenci\u00f3n en un servicio no disponible en la instituci\u00f3n remisora. Igualmente, para estos casos, est\u00e1 financiado con recursos de la UPC el traslado en ambulancia en caso de contrarreferencia. \/\/ El servicio de traslado cubrir\u00e1 el medio de transporte disponible en el sitio geogr\u00e1fico donde se encuentre el paciente, con base en su estado de salud, el concepto del m\u00e9dico tratante y el destino de la remisi\u00f3n, de conformidad con la normatividad vigente. \/\/ Asimismo, se financia el traslado en ambulancia del paciente remitido para atenci\u00f3n domiciliaria, si el m\u00e9dico as\u00ed lo prescribe\u201d. (Negrilla fuera del texto). \u00a0<\/p>\n<p>200 Como fundamento de esa afirmaci\u00f3n, la Sala Plena tuvo en cuenta los art\u00edculos 26 y 66 de la Resoluci\u00f3n 3512 de 2019. Esa norma estaba vigente al momento de la presentaci\u00f3n de la acci\u00f3n de tutela. Por lo tanto, resulta aplicable al caso concreto. En todo caso, esas disposiciones fueron sustituidas por los art\u00edculos 26 y 66 de la Resoluci\u00f3n 2481 de 2020. Sin embargo, esas normas tienen la misma orientaci\u00f3n.\u00a0 \u00a0<\/p>\n<p>Resoluci\u00f3n 2481 de 2020. \u201cArt\u00edculo 26. Atenci\u00f3n domiciliaria. La atenci\u00f3n en la modalidad extramural domiciliaria como alternativa a la atenci\u00f3n hospitalaria institucional est\u00e1 financiada con recursos de la UPC. en los casos que considere pertinente el profesional tratante, bajo las normas vigentes. Esta financiaci\u00f3n est\u00e1 dada s\u00f3lo para el \u00e1mbito de la salud. Par\u00e1grafo. En sustituci\u00f3n de la hospitalizaci\u00f3n institucional, conforme con la recomendaci\u00f3n m\u00e9dica, las EPS o las entidades que hagan sus veces, a trav\u00e9s de las IPS, ser\u00e1n responsables de garantizar las condiciones en el domicilio para esta modalidad de atenci\u00f3n seg\u00fan lo dispuesto en las normas vigentes\u201d. (Negrilla fuera del texto).\u00a0 \u00a0<\/p>\n<p>con internaci\u00f3n o la atenci\u00f3n domiciliaria del enfermo en fase terminal y de pacientes con enfermedad cr\u00f3nica, degenerativa e irreversible de alto impacto en la calidad de vida, de conformidad con lo establecido en la Ley 1733 de 2014, o aquella que la modifique o sustituya con las tecnolog\u00edas en salud y los servicios financiados con recursos de la UPC, seg\u00fan criterio del profesional tratante, salvo lo dispuesto en el par\u00e1grafo 4 del art\u00edculo 25 del presente acto administrativo\u201d. (Negrilla fuera del texto).\u00a0 \u00a0<\/p>\n<p>201 As\u00ed lo establec\u00eda el art\u00edculo 121 de la Resoluci\u00f3n 3512 de 2019, norma aplicable al momento de la presentaci\u00f3n de la acci\u00f3n de tutela. En todo caso, el contenido de esa disposici\u00f3n fue replicado en el art\u00edculo 121 de la Resoluci\u00f3n 2481 de 2020, \u201cPor la cual se actualizan integralmente los servicios y tecnolog\u00edas de salud financiados con recursos de la Unidad de Pago por Capitaci\u00f3n (UPC)\u201d, as\u00ed: \u201cLos servicios y tecnolog\u00edas de salud financiados con recursos de la UPC, incluyen el traslado acu\u00e1tico, a\u00e9reo y terrestre (en ambulancia b\u00e1sica o medicalizada), en los siguientes casos: \/\/ 1. Movilizaci\u00f3n de pacientes con patolog\u00eda de urgencias, desde el sitio de ocurrencia de la misma, hasta una instituci\u00f3n hospitalaria, incluyendo el servicio prehospitalario y de apoyo terap\u00e9utico en ambulancia. \/\/ 2. Entre IPS dentro del territorio nacional de los pacientes remitidos, teniendo en cuenta las limitaciones en la oferta de servicios de la instituci\u00f3n en donde est\u00e1n siendo atendidos, que requieran de atenci\u00f3n en un servicio no disponible en la instituci\u00f3n remisora. Igualmente, para estos casos, est\u00e1 financiado con recursos de la UPC el traslado en ambulancia en caso de contrarreferencia. \/\/ El servicio de traslado cubrir\u00e1 el medio de transporte disponible en el sitio geogr\u00e1fico donde se encuentre el paciente, con base en su estado de salud, el concepto del m\u00e9dico tratante y el destino de la remisi\u00f3n, de conformidad con la normatividad vigente. \/\/ Asimismo, se financia el traslado en ambulancia del paciente remitido para atenci\u00f3n domiciliaria, si el m\u00e9dico as\u00ed lo prescribe\u201d. (Negrilla fuera del texto). \u00a0 \u00a0<\/p>\n<p>202 En consecuencia, si no existe prescripci\u00f3n m\u00e9dica para el traslado del paciente en ambulancia b\u00e1sica o medicalizada, el juez deber\u00e1 verificar con la historia cl\u00ednica o con las pruebas allegadas al proceso, si el traslado es necesario para el tratamiento de la persona. Esto por cuanto constituye un hecho notorio. De ser as\u00ed, ordenar\u00e1 su suministro con la condici\u00f3n de una posterior ratificaci\u00f3n por parte de un profesional de la salud. En estos eventos, no es exigible el requisito de la incapacidad econ\u00f3mica.\u00a0 \u00a0<\/p>\n<p>Con todo, en caso de no contar con las pruebas mencionadas, el juez podr\u00e1 amparar el derecho a la salud en su faceta de diagn\u00f3stico. Para el efecto, podr\u00e1 ordenar a la EPS que, a trav\u00e9s de una valoraci\u00f3n m\u00e9dica, determine la necesidad de prescribir el transporte requerido en sede de tutela. Lo anterior, siempre que considere imperativo, a partir de un indicio razonable sobre la afectaci\u00f3n a la salud del accionante, otorgar una orden de protecci\u00f3n. Ver al respecto: Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos. \u00a0<\/p>\n<p>203 Ver al respecto: Sentencia T-130 de 2021, M.P. Paola Andrea Meneses Mosquera; T-512 de 2020, M.P. Alejandro Linares Cantillo; T-475 de 2020, M.P. Alejandro Linares Cantillo; T-419 de 2019, M.P. Gloria Stella Ortiz Delgado; y, T-260 de 2017, M.P. Alberto Rojas R\u00edos. \u00a0<\/p>\n<p>204 En aplicaci\u00f3n de las reglas mencionadas, esta Corporaci\u00f3n ha concedido, en varias oportunidades, el suministro de los costos del transporte para el paciente y su acompa\u00f1ante. A manera de ejemplo, en la Sentencia T-419 de 2019, M.P. Gloria Stella Ortiz Delgado, esta Corporaci\u00f3n orden\u00f3 a la EPS tratante suministrar el transporte intraurbano al paciente con su acompa\u00f1ante. En esa oportunidad, esta Corporaci\u00f3n estudi\u00f3 el caso de un menor de edad diagnosticado con autismo de la ni\u00f1ez y con perturbaci\u00f3n de la actividad y de la atenci\u00f3n. Como parte de su patolog\u00eda, padec\u00eda de un grado severo de hipersensibilidad al ruido. Por esa raz\u00f3n, no pod\u00eda trasladarse en transporte p\u00fablico. Sin embargo, su familia no contaba con los recursos econ\u00f3micos para acceder al transporte adecuado que respondiera a las necesidades del ni\u00f1o. De manera que, la entidad encontr\u00f3 cumplidos los requisitos jurisprudenciales para conceder el suministro del servicio solicitado por la representante legal del menor de edad. Para fundamentar esa decisi\u00f3n, reiter\u00f3 las sentencias T- 1158 de 2001, M.P. Marco Gerardo Monroy Cabra; T-346 de 2009, M.P. Mar\u00eda Victoria Calle Correa; T-636 de 2010, M.P. Nilson Pinilla Pinilla; T-557 de 2016, M.P. Alberto Rojas R\u00edos; T-674 de 2016, M.P. Gabriel Eduardo Mendoza Martelo.\u00a0 \u00a0<\/p>\n<p>205 En cuanto al requisito de incapacidad econ\u00f3mica del paciente y su familia, la jurisprudencia ha precisado que el actor debe probarla por cualquier medio. Si el accionante afirma de manera gen\u00e9rica que no dispone de recursos econ\u00f3micos, debe presumirse su buena fe. En ese sentido, la carga de la prueba se traslada a la EPS. Con todo, es posible que la afirmaci\u00f3n del demandante no demuestre con certeza su condici\u00f3n socioecon\u00f3mica. En ese evento, le corresponde al juez de tutela establecer dicha situaci\u00f3n. Sentencia T-409 de 2019, M.P. Gloria Stella Ortiz Delgado. Al respecto, reiter\u00f3 las Sentencias T-032 de 2018, M.P. Jos\u00e9 Fernando Reyes Cuartas; T-260 de 2017, M.P. Alberto Rojas R\u00edos; T-062 de 2017, M.P. Gabriel Eduardo Mendoza Martelo; y, T-683 de 2003, M.P. Luis Ernesto Vargas Silva; entre otras.\u00a0 \u00a0<\/p>\n<p>206 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos. Reitera la Sentencia T-471 de 2018., M.P. Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>207 MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos. \u00a0<\/p>\n<p>208 Seg\u00fan el numeral 6 del art\u00edculo 8 de la Resoluci\u00f3n 3512 de 2019, norma vigente al momento de presentar la tutela y por tanto aplicable al caso concreto, la atenci\u00f3n domiciliaria es la \u201cmodalidad extramural de prestaci\u00f3n de servicios de salud extrahospitalaria que busca brindar una soluci\u00f3n a los problemas de salud en el domicilio o residencia y que cuenta con el apoyo de profesionales, t\u00e9cnicos o auxiliares del \u00e1rea de la salud y la participaci\u00f3n de la familia\u201d. En todo caso, esa norma fue derogada por la Resoluci\u00f3n 2481 de 2020. Ese cuerpo normativo en su numeral 6 del art\u00edculo 8 establece, en t\u00e9rminos similares, que la atenci\u00f3n domiciliaria es \u201cel conjunto de procesos a trav\u00e9s de los cuales se materializa la prestaci\u00f3n de servicios de salud a una persona en su domicilio o residencia correspondiendo a una modalidad de prestaci\u00f3n de servicios de salud extramural\u201d. \u00a0<\/p>\n<p>209 Como fundamento de esa afirmaci\u00f3n, la Sala Plena tuvo en cuenta los art\u00edculos 26 y 66 de la Resoluci\u00f3n 3512 de 2019. Esa norma estaba vigente al momento de la presentaci\u00f3n de la acci\u00f3n de tutela. Por lo tanto, resulta aplicable al caso concreto. En todo caso, esas disposiciones fueron sustituidas por los art\u00edculos 26 y 66 de la Resoluci\u00f3n 2481 de 2020. Sin embargo, esas normas tienen la misma orientaci\u00f3n.\u00a0 \u00a0<\/p>\n<p>Resoluci\u00f3n 2481 de 2020. \u201cArt\u00edculo 26. Atenci\u00f3n domiciliaria. La atenci\u00f3n en la modalidad extramural domiciliaria como alternativa a la atenci\u00f3n hospitalaria institucional est\u00e1 financiada con recursos de la UPC. en los casos que considere pertinente el profesional tratante, bajo las normas vigentes. Esta financiaci\u00f3n est\u00e1 dada s\u00f3lo para el \u00e1mbito de la salud. Par\u00e1grafo. En sustituci\u00f3n de la hospitalizaci\u00f3n institucional, conforme con la recomendaci\u00f3n m\u00e9dica, las EPS o las entidades que hagan sus veces, a trav\u00e9s de las IPS, ser\u00e1n responsables de garantizar las condiciones en el domicilio para esta modalidad de atenci\u00f3n seg\u00fan lo dispuesto en las normas vigentes\u201d. (Negrilla fuera del texto).\u00a0 \u00a0<\/p>\n<p>Resoluci\u00f3n 2481 de 2020. Art\u00edculo 66. \u201cArt\u00edculo 66. Atenci\u00f3n paliativa. Los servicios y tecnolog\u00edas de salud financiados con recursos de la UPC, incluyen los cuidados paliativos en la atenci\u00f3n ambulatoria, la atenci\u00f3n \u00a0<\/p>\n<p>con internaci\u00f3n o la atenci\u00f3n domiciliaria del enfermo en fase terminal y de pacientes con enfermedad cr\u00f3nica, degenerativa e irreversible de alto impacto en la calidad de vida, de conformidad con lo establecido en la Ley 1733 de 2014, o aquella que la modifique o sustituya con las tecnolog\u00edas en salud y los servicios financiados con recursos de la UPC, seg\u00fan criterio del profesional tratante, salvo lo dispuesto en el par\u00e1grafo 4 del art\u00edculo 25 del presente acto administrativo\u201d. (Negrilla fuera del texto).\u00a0 \u00a0<\/p>\n<p>210 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>211 Sentencia SU-508 de 2020, MM.PP. \u00a0Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>212 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>213 Resoluci\u00f3n 244 de 31 de enero de 2019, \u201cPor la cual se adopta el listado de servicios y tecnolog\u00edas que ser\u00e1n excluidas de la financiaci\u00f3n con recursos p\u00fablicos asignados a la salud\u201d. Art\u00edculo 1: \u201cAd\u00e1ptese el listado de servicios y tecnolog\u00edas que ser\u00e1n excluidos de la financiaci\u00f3n con recursos p\u00fablicos asignados a la salud, el cual se encuentra contenido en el &#8220;Anexo T\u00e9cnico&#8221; que forma parte integral del presente acto administrativo\u201d.\u00a0 \u00a0<\/p>\n<p>214 \u201cQue la ausencia del servicio o tecnolog\u00eda en salud excluido lleve a la amenaza o vulneraci\u00f3n de los derechos a la vida o la integridad f\u00edsica del paciente, bien sea porque se pone en riesgo su existencia o se ocasione un deterioro del estado de salud vigente, claro y grave que impida que \u00e9sta se desarrolle en condiciones dignas. Sobre este presupuesto, la Sala Plena encuentra necesario precisar que para su superaci\u00f3n es necesario que exista una clara afectaci\u00f3n a la salud y no basta con la sola afirmaci\u00f3n sobre el deterioro de la dignidad humana. \u00a0De tal forma, la afectaci\u00f3n de la salud debe ser cualificada en los anteriores t\u00e9rminos, comoquiera que compromete la inaplicaci\u00f3n de las restricciones avaladas por el mecanismo participativo bajo criterios t\u00e9cnicos y cient\u00edficos y, por consiguiente, impacta la garant\u00eda de prestaci\u00f3n a cargo del Estado y la correlativa financiaci\u00f3n de los servicios que se requieren\u201d. Sentencia C-313 de 2014, M.P. Gabriel Eduardo Mendoza Martelo.\u00a0 \u00a0<\/p>\n<p>215 \u201cQue no exista dentro del plan de beneficios otro servicio o tecnolog\u00eda en salud que supla al excluido con el mismo nivel de efectividad para garantizar el m\u00ednimo vital del afiliado o beneficiario\u201d. Ibid.\u00a0 \u00a0<\/p>\n<p>216 \u201cQue el paciente carezca de los recursos econ\u00f3micos suficientes para sufragar el costo del servicio o tecnolog\u00eda en salud y carezca de posibilidad alguna de lograr su suministro a trav\u00e9s de planes complementarios de salud, medicina prepagada o programas de atenci\u00f3n suministrados por algunos empleadores\u201d. Ibid.\u00a0 \u00a0<\/p>\n<p>217 \u201cQue el servicio o tecnolog\u00eda en salud excluido del plan de beneficios haya sido ordenado por el m\u00e9dico tratante del afiliado o beneficiario, profesional que debe estar adscrito a la entidad prestadora de salud a la que se solicita el suministro\u201d. Ibid.\u00a0 \u00a0<\/p>\n<p>218 Sentencia SU-508 de 2020, MM.PP. Jos\u00e9 Fernando Reyes Cuartas y Alberto Rojas R\u00edos.\u00a0 \u00a0<\/p>\n<p>219 Valoraci\u00f3n m\u00e9dica del 7 de octubre de 2021. En expediente. Documento remitido por correo electr\u00f3nico: \u201cHistoria cl\u00ednica domiciliarios.pdf\u201d. Folios16 a 22. \u00a0<\/p>\n<p>220 Derecho de petici\u00f3n Q-841962 del 13 de noviembre de 2019. En expediente. Cuaderno 1. Folios 29 y 30.\u00a0 \u00a0<\/p>\n<p>221 Respuesta de FAMISANAR E.P.S. a queja de radicado Q-841962. En expediente. Cuaderno 1. Folio 40.\u00a0 \u00a0<\/p>\n<p>222 Transcrito en escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folio 6. \u00a0<\/p>\n<p>223 De conformidad con las cifras reportadas por el DANE, la expectativa de vida en Colombia para ambos sexos en el a\u00f1o 2020 era de 76 a\u00f1os. Esta proyecci\u00f3n vari\u00f3 significativamente para el a\u00f1o 2021. Seg\u00fan la entidad, para el 2021 la expectativa de vida para hombres es de 73,7 a\u00f1os, mientras que para mujeres es de 80 a\u00f1os. La accionante cuenta con 86 a\u00f1os. Es decir, que supera el promedio de expectativa de vida en Colombia. Departamento Administrativo Nacional de Estad\u00edstica (@DANE_Colombia). \u201cLa esperanza de vida al nacer, para 2021, es de 80 a\u00f1os para las mujeres y 73,7 a\u00f1os para los hombres en el total nacional. En las cabeceras, la esperanza de vida al nacer es mayor que en las zonas rurales\u201d #DANELecuenta bit.ly\/3nEGojP 12 de enero de 2021, [Tuit] https:\/\/twitter.com\/DANE_Colombia\/status\/1348991535417798656?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1348991540576870403%7Ctwgr%5E%7Ctwcon%5Es2_&amp;ref_url=https%3A%2F%2Fwww.eltiempo.com%2Feconomia%2Fsectores%2Fdane-revela-expectativa-de-vida-en-colombia-581272 [consulta 16 de septiembre de 2021].\u00a0 \u00a0<\/p>\n<p>224 Ver al respecto las sentencias T-221 de 2021, M.P. Diana Fajardo Rivera; y, SU-508 de 2020, MM.PP. Alberto Rojas R\u00edos y Jos\u00e9 Fernando Reyes Cuartas.\u00a0 \u00a0<\/p>\n<p>225 Ley 1751 de 2015. Art\u00edculo 11. \u201cLa atenci\u00f3n de ni\u00f1os, ni\u00f1as y adolescentes, mujeres en estado de embarazo, desplazados, v\u00edctimas de violencia y del conflicto armado, la poblaci\u00f3n adulta mayor, personas que sufren de enfermedades hu\u00e9rfanas y personas en condici\u00f3n de discapacidad, gozar\u00e1n de especial protecci\u00f3n por parte del Estado. Su atenci\u00f3n en salud no estar\u00e1 limitada por ning\u00fan tipo de restricci\u00f3n administrativa o econ\u00f3mica. Las instituciones que hagan parte del sector salud deber\u00e1n definir procesos de atenci\u00f3n intersectoriales e interdisciplinarios que le garanticen las mejores condiciones de atenci\u00f3n. \/\/ En el caso de las mujeres en estado de embarazo, se adoptar\u00e1n medidas para garantizar el acceso a los servicios de salud que requieren durante el embarazo y con posterioridad al mismo y para garantizar que puedan ejercer sus derechos fundamentales en el marco del acceso a servicios de salud. \/\/ PAR\u00c1GRAFO 1o. Las v\u00edctimas de cualquier tipo de violencia sexual tienen derecho a acceder de manera prioritaria a los tratamientos sicol\u00f3gicos y siqui\u00e1tricos que requieran. \/\/ PAR\u00c1GRAFO 2o. En el caso de las personas v\u00edctimas de la violencia y del conflicto armado, el Estado desarrollar\u00e1 el programa de atenci\u00f3n psicosocial y salud integral a las v\u00edctimas de que trata el art\u00edculo 137 de la Ley 1448 de 2011\u201d.\u00a0 \u00a0<\/p>\n<p>226 Derecho de petici\u00f3n Q-841962 del 13 de noviembre de 2019. En expediente. Cuaderno 1. Folios 29 y 30.\u00a0 \u00a0<\/p>\n<p>227 Respuesta de FAMISANAR E.P.S. a queja de radicado Q-841962. En expediente. Cuaderno 1. Folio 40.\u00a0 \u00a0<\/p>\n<p>228 Transcrito en escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folio 6. \u00a0<\/p>\n<p>229 Transcrito en escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folio 6. \u00a0<\/p>\n<p>230 Historias cl\u00ednicas de la accionante con valoraciones previas al 21 de febrero de 2020. En expediente. Cuaderno 1. Folios 42 a 60, y 96.\u00a0 \u00a0<\/p>\n<p>231 Escrito de acci\u00f3n de tutela. En expediente. Cuaderno 1. Folios 6 y 7 \u00a0<\/p>\n<p>232 Historia cl\u00ednica del 26 de febrero de 2020. Consulta externa. Aportada con la impugnaci\u00f3n. En expediente. Cuaderno 1. Folio 96.\u00a0 \u00a0<\/p>\n<p>233 \u201cEn cuanto a los efectos de la diabetes sobre la hidrataci\u00f3n de la piel, los resultados de las observaciones cl\u00ednicas y experimentales son controversiales. La alta prevalencia de xerosis entre los diab\u00e9ticos (44 %) se ha relacionado tanto con alteraciones en la funci\u00f3n de barrera de la piel como con las variaciones en la humedad del ambiente (6,10). Sin embargo, aunque la xerosis no sea cl\u00ednicamente evidente, el proceso natural de recambio epid\u00e9rmico est\u00e1 alterado (6). Tambi\u00e9n se ha documentado una menor actividad de las gl\u00e1ndulas seb\u00e1ceas (11) y un desequilibrio en la composici\u00f3n de los l\u00edpidos del estrato c\u00f3rneo, dado por la reducci\u00f3n en los niveles de los \u00e1cidos grasos libres (12). Por lo tanto, las anormalidades que se presentan en la funci\u00f3n de la barrera de la piel de los diab\u00e9ticos podr\u00edan ser consecuencia de su fragilidad estructural y del desarrollo defectuoso de sus c\u00e9lulas epid\u00e9rmicas. [\u2026] En todos los casos se recomienda el control de la xerosis con emolientes y cuidados generales como evitar el rascado y el trauma en las extremidades y en las zonas afectadas por cualquier dermatosis\u201d. Ibid. P. 241 y 246.\u00a0 \u00a0<\/p>\n<p>235 Valoraci\u00f3n m\u00e9dica del 13 de noviembre de 2019. Consulta domiciliaria. En expediente. Cuaderno 1. Folio 44.\u00a0 \u00a0<\/p>\n<p>236 Historias cl\u00ednicas de la accionante con valoraciones previas al 21 de febrero de 2020. En expediente. Cuaderno 1. Folios 42 a 60, y 96. \u00a0<\/p>\n<p>237 Ibid. \u00a0<\/p>\n<p>238 Constituci\u00f3n Pol\u00edtica. Art\u00edculo 277. Numeral 1. \u201cEl Procurador General de la Naci\u00f3n, por s\u00ed o por medio de sus delegados y agentes, tendr\u00e1 las siguientes funciones: \/\/ 1. Vigilar el cumplimiento de la Constituci\u00f3n, las leyes, las decisiones judiciales y los actos administrativos [\u2026]\u201d.\u00a0 \u00a0<\/p>\n<p>239 Al respecto, la Sala Plena ha reconocido que \u201c[f]rente a un fallo de tutela el deber principal del juez es de hacerlo cumplir. Y para ello, el instrumento m\u00e1s id\u00f3neo es el tr\u00e1mite de cumplimiento, que puede ser solicitado, de manera simult\u00e1nea o sucesiva, por el beneficiario del fallo. En materia de competencia para conocer del tr\u00e1mite de cumplimiento, la regla es que el competente es el juez de tutela de primera instancia [\u2026]\u201d. (Negrilla fuera del texto). Sentencia C-367 de 2014, M.P. Mauricio Gonz\u00e1lez Cuervo.\u00a0 \u00a0<\/p>\n<p>240 Decreto 2591 de 1991. Art\u00edculo 23. \u201cCuando la solicitud se dirija contra una acci\u00f3n de la autoridad el fallo que conceda la tutela tendr\u00e1 por objeto garantizar al agraviado el pleno goce de su derecho, y volver al estado anterior a la violaci\u00f3n, cuando fuere posible. \/\/ Cuando lo impugnado hubiere sido la denegaci\u00f3n de un acto o una omisi\u00f3n, el fallo ordenar\u00e1 realizarlo o desarrollar la acci\u00f3n adecuada, para lo cual se otorgar\u00e1 un plazo prudencial perentorio. Si la autoridad no expide el acto administrativo de alcance particular u lo remite al juez en el t\u00e9rmino de 48 horas, \u00e9ste podr\u00e1 disponer lo necesario para que el derecho sea libremente ejercido sin m\u00e1s requisitos. Si se hubiere tratado de una mera conducta o actuaci\u00f3n material, o de una amenaza, se ordenar\u00e1 su inmediata cesaci\u00f3n, as\u00ed como evitar toda nueva violaci\u00f3n o amenaza, perturbaci\u00f3n o restricci\u00f3n. \/\/ En todo caso, el juez establecer\u00e1 los dem\u00e1s efectos del fallo para el caso concreto\u201d.\u00a0 \u00a0<\/p>\n<p>Decreto 2591 de 1991. Art\u00edculo 27. \u201cProferido el fallo que conceda la tutela, la autoridad responsable del agravio deber\u00e1 cumplirla sin demora. \/\/ Si no lo hiciere dentro de las cuarenta y ocho horas siguientes, el juez se dirigir\u00e1 al superior del responsable y le requerir\u00e1 para que lo haga cumplir y abra el correspondiente procedimiento disciplinario contra aqu\u00e9l. Pasadas otras cuarenta y ocho horas, ordenar\u00e1 abrir proceso contra el superior que no hubiere procedido conforme a lo ordenado y adoptar\u00e1 directamente todas las medidas para el cabal cumplimiento del mismo. El juez podr\u00e1 sancionar por desacato al responsable y al superior hasta que cumplan su sentencia. \/\/ Lo anterior sin perjuicio de la responsabilidad del funcionario en su caso. \/\/ En todo caso, el juez establecer\u00e1 los dem\u00e1s efectos del fallo para el caso concreto y mantendr\u00e1 la competencia hasta que est\u00e9 completamente restablecido el derecho o eliminadas las causas de la amenaza\u201d.\u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia T-394\/21 \u00a0 DERECHO A LA SALUD Y A LA VIDA-Vulneraci\u00f3n cuando se hace nugatorio el derecho al diagn\u00f3stico \u00a0 DERECHO A LA SALUD DE PERSONA DE LA TERCERA EDAD-Vulneraci\u00f3n por EPS por omisi\u00f3n en la autorizaci\u00f3n y suministro de insumos y tecnolog\u00edas \u00a0 PRINCIPIO DE SUBSIDIARIEDAD COMO REQUISITO DE PROCEDIBILIDAD DE LA [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[],"class_list":["post-28141","post","type-post","status-publish","format-standard","hentry","category-tutelas-2021"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/28141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=28141"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/28141\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=28141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=28141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=28141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}