{"id":30206,"date":"2024-12-09T21:05:33","date_gmt":"2024-12-09T21:05:33","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-023-24-2\/"},"modified":"2024-12-09T21:05:33","modified_gmt":"2024-12-09T21:05:33","slug":"t-023-24-2","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-023-24-2\/","title":{"rendered":"T-023-24"},"content":{"rendered":"\n<p><\/p>\n<p>TEMAS-SUBTEMAS<\/p>\n<p>Sentencia T-023\/24<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Procedencia por defecto procedimental<\/p>\n<p>(El juez accionado) desconoci\u00f3 los postulados procesales dispuestos para (i) el reconocimiento de los poderes especiales presentados ante notarios p\u00fablicos en el marco de un proceso judicial (Art\u00edculos 73 y siguientes del C\u00f3digo General del Proceso y Decretos 960 de 1970 y 1069 de 2015); (ii) la comprobaci\u00f3n de la existencia y representaci\u00f3n legal de las personas jur\u00eddicas privadas (Art\u00edculo 85 del C\u00f3digo General del Proceso); (iii) la configuraci\u00f3n del desistimiento t\u00e1cito, en particular, advertencia clara de la carga procesal que debe cumplir la parte so pena de finalizar el proceso anticipadamente (Art\u00edculo 317 del C\u00f3digo General del Proceso); (iv) y el tr\u00e1mite del recurso de apelaci\u00f3n contra las decisiones que decreten el desistimiento t\u00e1cito y terminan el proceso (Numeral 5 del art\u00edculo 317, art\u00edculo 320 y numeral 7 del art\u00edculo 321 del C\u00f3digo General del Proceso).<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Requisitos generales y especiales de procedibilidad<\/p>\n<p>ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-En la aplicaci\u00f3n del principio de inmediatez, la fecha que debe tomarse en consideraci\u00f3n para determinar la procedencia de la tutela, es la de la providencia en la cual se le puso fin al proceso<\/p>\n<p>DERECHO AL DEBIDO PROCESO-Finalidad<\/p>\n<p>ACCESO A LA ADMINISTRACION DE JUSTICIA-Prevalencia del derecho sustancial sobre lo adjetivo o formal<\/p>\n<p>DERECHO A LA DEFENSA TECNICA-Jurisprudencia constitucional<\/p>\n<p>DERECHO A LA DEFENSA TECNICA-Garant\u00eda del debido proceso<\/p>\n<p>DERECHO DE POSTULACION-Definici\u00f3n<\/p>\n<p>REPRESENTACION JUDICIAL DE LAS PERSONAS JURIDICAS-Jurisprudencia constitucional<\/p>\n<p>PERSONA JURIDICA-Prueba de la representaci\u00f3n legal<\/p>\n<p>(&#8230;) en los procesos judiciales donde alguna de las partes sea una persona jur\u00eddica, el Juez debe, primero, consultar su existencia y representaci\u00f3n en las bases de datos de las entidades que tienen a su cargo el deber de certificarla y, despu\u00e9s, y solo en el supuesto de que dicha informaci\u00f3n no est\u00e9 disponible en tales bases de datos, podr\u00e1 exigir este certificado a la parte.<\/p>\n<p>DESISTIMIENTO TACITO-Concepto\/DESISTIMIENTO TACITO-Modalidades\/DESISTIMIENTO TACITO-Procedimiento para su determinaci\u00f3n\/DESISTIMIENTO TACITO-Requisitos<\/p>\n<p>DESISTIMIENTO TACITO-Fines constitucionales<\/p>\n<p>(&#8230;) el desistimiento t\u00e1cito, adem\u00e1s de ser entendido como una sanci\u00f3n procesal que se configura ante el incumplimiento de las cargas procesales del demandante, opera como garante de: (i) el derecho de todas las personas a acceder a una administraci\u00f3n de justicia diligente, c\u00e9lere, eficaz y eficiente; (ii) la posibilidad de obtener pronta y cumplida justicia y (ii) el acceso material a la justicia, en favor de quienes conf\u00edan al Estado la soluci\u00f3n de sus conflictos. Todo esto en el entendido de que la racionalizaci\u00f3n del trabajo judicial y la descongesti\u00f3n del aparato jurisdiccional, finalidades a las que aporta la decisi\u00f3n de terminar anticipadamente un tr\u00e1mite judicial, contribuyen significativamente a hacer m\u00e1s expedito el tr\u00e1mite de los litigios judiciales.<\/p>\n<p>REP\u00daBLICA DE COLOMBIA<\/p>\n<p>CORTE CONSTITUCIONAL<\/p>\n<p>Sala Sexta de Revisi\u00f3n<\/p>\n<p>SENTENCIA T-023 DE 2024<\/p>\n<p>Referencia: Expediente T-9.390.592<\/p>\n<p>Demandante: Cenit Transporte y Log\u00edstica de Hidrocarburos S.A.S.<\/p>\n<p>Demandada: Juzgado Primero Civil Municipal de Villavicencio (Meta)<\/p>\n<p>Magistrado sustanciador:<\/p>\n<p>ANTONIO JOS\u00c9 LIZARAZO OCAMPO<\/p>\n<p>Bogot\u00e1 D.C., cinco (05) de febrero de dos mil veinticuatro (2024)<\/p>\n<p>La Sala Sexta de Revisi\u00f3n, en ejercicio de sus competencias constitucionales y legales, decide sobre la revisi\u00f3n de los fallos de tutela proferidos dentro del expediente de la referencia.<\/p>\n<p>ANTECEDENTES<\/p>\n<p>Hechos relevantes<\/p>\n<p>1. 1. \u00a0El 1 de febrero de 2013, Ecopetrol S.A present\u00f3 una demanda de solicitud de aval\u00fao de perjuicios y decreto de indemnizaci\u00f3n por imposici\u00f3n de servidumbre petrolera, en contra de Ra\u00fal Ariza Santoyo y \u00c1ngela Consuelo Castro Castro, en su calidad de propietarios del predio denominado \u201cEl Amparo\u201d, ubicado en la vereda Ca\u00f1o Negro del municipio de Villavicencio, (Meta), e identificado con el Folio de Matricula Inmobiliaria N\u00famero 320-8119. \u00a0As\u00ed mismo, conforme a lo estipulado en la Ley 1274 de 2009, pidi\u00f3 la ocupaci\u00f3n y el ejercicio provisional de la servidumbre petrolera y, finalmente, como medida cautelar, requiri\u00f3 la inscripci\u00f3n de la demanda en el Folio de Matricula Inmobiliaria del predio \u201cEl Amparo\u201d, de conformidad con lo dispuesto en el art\u00edculo 692 del C\u00f3digo de Procedimiento Civil, vigente para ese momento.<\/p>\n<p>2. El 18 de julio de 2013, el Juzgado Primero Civil Municipal de Villavicencio admiti\u00f3 la demanda, corri\u00f3 traslado a la parte demandada, orden\u00f3 su inscripci\u00f3n en el Folio de Matricula Inmobiliaria del predio \u201cEl Amparo\u201d, y design\u00f3 un perito del listado de auxiliares de la justicia, a fin de que realizara el aval\u00fao de los perjuicios causados con la servidumbre petrolera. \u00a0Igualmente, de acuerdo con el numeral 6 del art\u00edculo 5 de la Ley 1274 de 2009, autoriz\u00f3 la ocupaci\u00f3n y el ejercicio provisional de la servidumbre de hidrocarburos solicitada sobre dicho predio.<\/p>\n<p>3. El 02 de marzo 2016, Ecopetrol y Cenit Transporte y Log\u00edstica de Hidrocarburos S.A.S. (en adelante Cenit o el accionante) suscribieron una cesi\u00f3n de derechos litigiosos, en la que se relacion\u00f3 el predio \u201cEl Amparo\u201d, objeto del proceso de solicitud de aval\u00fao de servidumbre petrolera. El 11 de agosto de 2016, el Juzgado acept\u00f3 esta cesi\u00f3n de derechos y reconoci\u00f3 como apoderado de Cenit al abogado Juan Manuel Garrido D\u00edaz, quien tambi\u00e9n era apoderado de Ecopetrol.<\/p>\n<p>4. El 15 de noviembre de 2017, el Juzgado Primero Civil Municipal de Villavicencio solicit\u00f3 al Instituto Colombiano Agust\u00edn Codazzi que designara un auxiliar de la justicia a fin de determinar el valor de los perjuicios causados por la imposici\u00f3n de la servidumbre petrolera. Lo anterior, debido a que desde la admisi\u00f3n de la demanda hasta ese momento las designaciones de peritos realizadas por el despacho hab\u00edan sido infructuosas.<\/p>\n<p>5. El 22 de mayo de 2018, el Instituto Geogr\u00e1fico Agust\u00edn Codazzi, en respuesta a la solicitud del Juzgado Primero, requiri\u00f3 la siguiente documentaci\u00f3n para la realizaci\u00f3n del aval\u00fao objeto del proceso: (i) plano de localizaci\u00f3n del inmueble objeto de aval\u00fao con indicaci\u00f3n de \u00e1reas (terreno, construcci\u00f3n y mejoras); (ii) copia de la escritura; (iii) certificado de Tradici\u00f3n y Libertad y (iv) certificado de la norma de usos de suelos. El 29 de junio de 2018, el Juzgado Primero puso en conocimiento de dicho requerimiento al accionante y le solicit\u00f3 que, en el t\u00e9rmino de diez (10) d\u00edas contados a partir de la notificaci\u00f3n de dicho auto, presentara la documentaci\u00f3n exigida por el Instituto Agust\u00edn Codazzi.<\/p>\n<p>6. El 30 de agosto de 2018, el accionante le inform\u00f3 al Juzgado Primero que el 3 de julio hab\u00eda allegado directamente al Instituto Agust\u00edn Codazzi la documentaci\u00f3n requerida. Tambi\u00e9n advirti\u00f3 que el certificado de la norma de usos de suelos estaba en tr\u00e1mite ante la Curadur\u00eda Urbana Municipal y que tan pronto lo obtuviera lo remitir\u00eda. El 7 de septiembre de 2018, el Juzgado Primero incorpor\u00f3 esta documentaci\u00f3n al expediente y ofici\u00f3 al Instituto Agust\u00edn Codazzi para que designara un auxiliar judicial que realizara el aval\u00fao requerido.<\/p>\n<p>7. El 14 de febrero de 2019, Cenit radic\u00f3 ante el Juzgado Primero un poder especial otorgado por Jairo Enrique Corredor Castilla, en calidad de apoderado general de la empresa, a favor del abogado Jhorman Alexis \u00c1lvarez Fierro, para que ejerciera a partir de ese momento la representaci\u00f3n judicial de la empresa en dicho proceso. El 3 de mayo de 2019, el Juzgado Primero dispuso que, antes de dar tr\u00e1mite al poder allegado por el accionante, se deb\u00eda acreditar en debida forma la calidad del se\u00f1or Jairo Enrique Corredor Castilla como apoderado general de la empresa. As\u00ed mismo, acept\u00f3 la renuncia del poder allegado por el abogado Juan Manuel Garrido D\u00edaz.<\/p>\n<p>8. El 10 de junio de 2019, el Instituto Agust\u00edn Codazzi, en atenci\u00f3n a un oficio emitido el 30 de mayo de 2019 por el Juzgado Primero, requiri\u00f3 nuevamente la siguiente documentaci\u00f3n para la realizaci\u00f3n del aval\u00fao: (i) certificados expedidos por la Oficina de Planeaci\u00f3n Municipal y\/o Curadur\u00eda sobre normatividad vigente de uso del suelo permitido en la zona donde se ubica el predio a la fecha de solicitud del aval\u00fao; (ii) planos de localizaci\u00f3n donde se determinen las \u00e1reas que ser\u00e1n objeto de valoraci\u00f3n, tanto terreno, como construcciones; (iii) escrituras; (iv) certificados de tradici\u00f3n y libertad. El 19 de julio de 2019, el Juzgado Primero solicit\u00f3 al accionante que aportara dicha documentaci\u00f3n para la realizaci\u00f3n del aval\u00fao de perjuicios. El 23 de agosto de 2019, el Juzgado estableci\u00f3 que el accionante contaba con veinte (20) d\u00edas para allegar la documentaci\u00f3n solicitada.<\/p>\n<p>9. El 15 de noviembre de 2019, dado que el accionante no cumpli\u00f3 con lo ordenado en el auto del 19 de julio, el Juzgado Primero emiti\u00f3 un auto en el que dispuso que en el t\u00e9rmino de treinta (30) d\u00edas deb\u00eda realizar \u201ctodas y cada una de las actuaciones tenientes a prestar la colaboraci\u00f3n necesaria al Instituto Geogr\u00e1fico Agust\u00edn Codazzi para llevar a cabo el aval\u00fao de perjuicios que se causaron con la imposici\u00f3n de la servidumbre, so pena de dar aplicaci\u00f3n a lo dispuesto en el art\u00edculo 317 del C\u00f3digo General del Proceso\u201d.<\/p>\n<p>10. El 21 de enero de 2020, Jhorman Alexis \u00c1lvarez Fierro, en representaci\u00f3n de Cenit, remiti\u00f3 al Juzgado Primero un memorial en el que aportaba las constancias de cumplimiento al requerimiento realizado por el Instituto Agust\u00edn Codazzi, y adem\u00e1s se\u00f1alaba que quedaba pendiente \u00fanicamente el certificado del uso del suelo, que se encontraba en tr\u00e1mite ante la Oficina de Planeaci\u00f3n Municipal de Villavicencio.<\/p>\n<p>11. El 30 de enero de 2020, Ra\u00fal Ariza Santoyo y \u00c1ngela Consuelo Castro Castro, partes demandadas en el proceso de servidumbre petrolera, solicitaron al Juzgado Primero que aplicara el desistimiento t\u00e1cito y terminara anticipadamente el proceso, consagrado en el art\u00edculo 317 del C\u00f3digo General del Proceso, toda vez que el accionante no hab\u00eda cumplido con la carga procesal impuesta por el despacho en el auto del 15 de noviembre de 2019. Esto, por cuanto, a su juicio, (i) el abogado Jhorman Alexis \u00c1lvarez Fierro, qui\u00e9n hab\u00eda radicado la documentaci\u00f3n ante el Instituto Agust\u00edn Codazzi y el Juzgado, no contaba con personer\u00eda jur\u00eddica para actuar en el proceso, pues el despacho a\u00fan no lo hab\u00eda reconocido como representante de la parte demandante; y (ii) la documentaci\u00f3n aportada ante el Instituto Agust\u00edn Codazzi no cumpl\u00eda con los requerimientos exigidos, en tanto no se alleg\u00f3 el certificado del uso del suelo del predio, sino un derecho de petici\u00f3n del 21 de enero donde lo requer\u00eda a la Oficina de Planeaci\u00f3n municipal y, adem\u00e1s, el plano de localizaci\u00f3n del predio que se adjunt\u00f3 no contaba con las especificaciones t\u00e9cnicas requeridas.<\/p>\n<p>12. El 28 de febrero de 2020, el Juzgado Primero incorpor\u00f3 al expediente todos los documentos allegados por Jhorman Alexis \u00c1lvarez Fierro, pero advirti\u00f3 que los mismos no ser\u00edan tenidos en cuenta, toda vez que el abogado no cumpli\u00f3 con la carga impuesta en el auto del 3 de mayo de 2019, consistente en acreditar la calidad de la persona que le otorgaba el poder, a trav\u00e9s del certificado de c\u00e1mara y comercio. El accionante present\u00f3 recurso de reposici\u00f3n contra dicho auto, pero el Juzgado no le dio tr\u00e1mite por cuanto consider\u00f3 que \u201cno ostenta la expresi\u00f3n de las razones que lo sustentan, tal y como lo exige el p\u00e1rrafo tercero del art\u00edculo 318 del C.G.P\u201d. As\u00ed mismo, el despacho solicit\u00f3 a la secretar\u00eda que contabilizara el plazo restante con el que contaba el accionante para darle cumplimiento a lo ordenado en el auto del 15 de noviembre de 2019, esto es, la declaratoria del desistimiento t\u00e1cito.<\/p>\n<p>13. El 23 de octubre de 2020, el Juzgado Primero decidi\u00f3 aplicar el art\u00edculo 317 del C\u00f3digo General del Proceso y terminar anticipadamente el proceso por desistimiento t\u00e1cito, en la medida que \u201cla parte actora no cumpli\u00f3 con la carga procesal impuesta en el auto del 15 de noviembre de 2019\u201d.<\/p>\n<p>14. Contra dicha decisi\u00f3n, el accionante interpuso recurso de reposici\u00f3n y en subsidi\u00f3 apelaci\u00f3n. El primero fue resuelto desfavorablemente el 4 de junio de 2021 al considerar el despacho accionado (i) que nunca le reconoci\u00f3 personer\u00eda al abogado Jhorman Alexis \u00c1lvarez Fierro para actuar en el proceso como representante del accionante, debido a \u201cla falta de acreditaci\u00f3n del certificado de c\u00e1mara y comercio de la calidad del presunto gerente de Cenit\u201d; (ii) que \u201cpasaron pr\u00e1cticamente 2 a\u00f1os y medio desde la solicitud de la acreditaci\u00f3n hasta el d\u00eda que se declar\u00f3 el desistimiento t\u00e1cito\u201d; (iii) que la decisi\u00f3n de declarar el desistimiento t\u00e1cito iba \u201cconcatenada\u201d con la acreditaci\u00f3n de la calidad de la persona que otorg\u00f3 el poder, \u201cy por ende, con el reconocimiento de personer\u00eda para actuar en este proceso\u201d; (iv) que el abogado \u00c1lvarez Fierro \u201cguard\u00f3 silencio o desconoci\u00f3 la providencia que ordenaba la acreditaci\u00f3n del representante legal\u201d y de la misma forma desconoci\u00f3 \u201cla providencia que orden\u00f3 las actuaciones pertinentes para que no se configurara el desistimiento t\u00e1cito\u201d; (v) que si se hubiese aceptado la documentaci\u00f3n allegada por un abogado que no ten\u00eda personer\u00eda para actuar en el proceso, se generar\u00eda una violaci\u00f3n al debido proceso, especialmente al derecho de contradicci\u00f3n; y (vi) que seg\u00fan el C\u00f3digo de Comercio y la sentencia T-328 de 2002 de la Corte Constitucional, el certificado de existencia y representaci\u00f3n legal es un medio de prueba necesario para la acreditaci\u00f3n de la representaci\u00f3n legal de una persona jur\u00eddica.<\/p>\n<p>15. Finalmente, el Juzgado se\u00f1al\u00f3 que este recurso de reposici\u00f3n se resolv\u00eda en procura de la protecci\u00f3n del debido proceso de la entidad demandante, pese a que el abogado que lo present\u00f3 no estaba reconocido como tal en el proceso. Por otra parte, respecto al recurso de apelaci\u00f3n, el Juzgado concluy\u00f3 que no le dar\u00eda tr\u00e1mite por cuanto el abogado no contaba con personer\u00eda jur\u00eddica para interponerlo.<\/p>\n<p>16. El 11 de junio de 2021, el accionante present\u00f3 un recurso de reposici\u00f3n en contra de esta \u00faltima decisi\u00f3n al considerar que conten\u00eda puntos nuevos, relacionados con la representaci\u00f3n de la empresa Cenit en el proceso, que no se hab\u00edan incluido en el auto del 23 de octubre de 2020. En esa oportunidad alleg\u00f3 tambi\u00e9n la escritura p\u00fablica No.2271 de 14 de septiembre de 2017 donde Cenit otorgaba poder general a Javier Enrique Corredor Castilla, quien hab\u00eda sido la persona que le otorg\u00f3 el poder judicial el 14 de febrero de 2020 al abogado \u00c1lvarez Fierro.<\/p>\n<p>17. El 26 de agosto de 2021, el Juzgado Primero decidi\u00f3 no tramitar este recurso \u201cpor cuanto el auto que decide una reposici\u00f3n no es susceptible de ning\u00fan recurso, de conformidad con lo normado en el inciso 4 del art\u00edculo 318 del C\u00f3digo General del Proceso\u201d, y adicionalmente se\u00f1al\u00f3 que se trataba de puntos nuevos los alegados por el accionante.<\/p>\n<p>18. El 1 de septiembre de 2021, el accionante present\u00f3 un recurso de reposici\u00f3n contra esta \u00faltima determinaci\u00f3n del Juzgado Primero y, en subsidio, el recurso de queja contra el auto del 4 de junio de 2021. El 7 de octubre de 2021, interpuso tambi\u00e9n un incidente de nulidad contra todo lo actuado a partir del 28 de febrero de 2020.<\/p>\n<p>19. El 26 de octubre de 2022, el Juzgado decidi\u00f3 no darle tr\u00e1mite al recurso de reposici\u00f3n, toda vez que la providencia recurrida no era susceptible de ning\u00fan recurso de acuerdo con el inciso 4 del art\u00edculo 318 del C\u00f3digo General del Proceso. Frente al recurso de queja, el despacho lo deneg\u00f3 por considerarlo extempor\u00e1neo y por no haber sido interpuesto en la forma prevista en el art\u00edculo 353 del C\u00f3digo General del Proceso. Y finalmente, respecto a la solicitud de nulidad, se abstuvo de darle tr\u00e1mite al se\u00f1alar que el proceso hab\u00eda terminado.<\/p>\n<p>2. Solicitud de tutela y pretensiones<\/p>\n<p>20. El 07 de febrero de 2023, el accionante present\u00f3 una solicitud de tutela en contra el Juzgado Primero Civil Municipal de Villavicencio (Meta), por considerar que el despacho vulner\u00f3 sus derechos fundamentales al debido proceso, la tutela judicial efectiva y el acceso a la administraci\u00f3n de justicia, toda vez que, a su juicio, incurri\u00f3 en un defecto procedimental absoluto al decretar el desistimiento t\u00e1cito del proceso de solicitud de aval\u00fao de servidumbre petrolera. En consecuencia, solicit\u00f3 dejar sin efectos el auto del 23 de octubre de 2020, que declar\u00f3 el desistimiento t\u00e1cito, y ordenar la continuaci\u00f3n del proceso en la etapa procesal en la que se encontraba.<\/p>\n<p>21. Indic\u00f3 que dicho defecto procedimental por exceso ritual manifiesto se configur\u00f3 en dos actuaciones del Juzgado. La primera de ellas ser\u00eda la exigencia indebida de la acreditaci\u00f3n de la existencia y representaci\u00f3n legal de Cenit en el proceso de solicitud de aval\u00fao de servidumbre, como requisito para reconocer la personer\u00eda jur\u00eddica al abogado Jhorman Alexis \u00c1lvarez Fierro, y otorgarle valor a las actuaciones procesales adelantadas por \u00e9l. Al respecto, se\u00f1al\u00f3 que el 14 de febrero de 2019 hab\u00eda radicado ante el Juzgado Primero un poder especial otorgado por Jairo Enrique Corredor Castilla, en calidad de apoderado general de Cenit, a favor de Jhorman Alexis \u00c1lvarez Fierro, para que \u00e9ste ejerciera la representaci\u00f3n judicial de la empresa, y queno alleg\u00f3 el certificado de existencia y representaci\u00f3n legal de Cenit, dado que el art\u00edculo 85 del C\u00f3digo General del Proceso (C.G.P) dispone que \u201cla prueba de la existencia y representaci\u00f3n de las personas jur\u00eddicas de derecho privado solo podr\u00e1 exigirse cuando dicha informaci\u00f3n no conste en las bases de datos de las entidades p\u00fablicas y privadas que tengan a su cargo el deber de certificarla. Cuando la informaci\u00f3n est\u00e9 disponible por este medio, no ser\u00e1 necesario certificado alguno.\u201d Seg\u00fan su interpretaci\u00f3n de dicha norma, el certificado no debe aportarse ni exigirse obligatoriamente en todos los casos, como lo hizo el Juzgado accionado, sino solo cuando no conste la informaci\u00f3n en las bases de datos de las entidades p\u00fablicas y privadas, como las C\u00e1maras de Comercio.<\/p>\n<p>22. La segunda actuaci\u00f3n del Juzgado que habr\u00eda configurado el defecto procedimental, ser\u00eda la de declarar en el auto del 23 de octubre de 2020 el desistimiento t\u00e1cito del proceso de servidumbre petrolera, al interpretar incorrectamente que el accionante no hab\u00eda cumplido con la carga procesal que le hab\u00eda impuesto el despacho en el auto del 15 de noviembre de 2019. Indic\u00f3 que, contrario a lo interpretado por el Juzgado, \u00e9ste s\u00ed hab\u00eda cumplido la solicitud dentro del t\u00e9rmino de los 30 d\u00edas, quedando s\u00f3lo pendiente el certificado del uso del suelo, respecto del cual se acreditaron las gestiones tendientes a su obtenci\u00f3n. Se\u00f1al\u00f3 tambi\u00e9n que el Juzgado Primero entendi\u00f3 err\u00f3neamente que dicha carga procesal no se hab\u00eda cumplido al no reconocer la personer\u00eda jur\u00eddica al abogado representante de Cenit, y no reconocer los documentos allegados por \u00e9ste al expediente, declarando, en consecuencia, el desistimiento t\u00e1cito y la terminaci\u00f3n anticipada del proceso.<\/p>\n<p>3. Tr\u00e1mite procesal de las tutelas objeto de revisi\u00f3n<\/p>\n<p>23. La solicitud de tutela correspondi\u00f3 por reparto al Juzgado Quinto Civil del Circuito de Villavicencio, que mediante el auto del 07 de febrero de 2023, resolvi\u00f3 (i) admitir la acci\u00f3n de tutela; (ii) vincular a Ecopetrol y a los se\u00f1ores Ra\u00fal Ariza Santoyo y \u00c1ngela Consuelo Castro Castro, as\u00ed como a las dem\u00e1s partes e intervinientes del proceso de aval\u00fao de servidumbre petrolera; y (iii) correr traslado al Juzgado Primero y las dem\u00e1s partes vinculadas, para que se pronunciaran acerca de los hechos de la demanda.<\/p>\n<p>24. Contestaci\u00f3n del Juzgado Primero Civil Municipal de Villavicencio. Realiz\u00f3 un relato de las actuaciones adelantadas en el tr\u00e1mite del proceso de aval\u00fao de servidumbre petrolera y solicit\u00f3 negar la acci\u00f3n de tutela por cuanto no exist\u00eda material probatorio que evidenciara la presunta vulneraci\u00f3n de derechos que alegaba el demandante. Concluy\u00f3 que el despacho hab\u00eda actuado bajo los par\u00e1metros legales.<\/p>\n<p>25. Contestaci\u00f3n de Jos\u00e9 Daniel L\u00f3pez Vega. \u00a0Se\u00f1al\u00f3 que prest\u00f3 sus servicios como abogado de Ecopetrol hasta el 31 de marzo de 2014 y que mientras estaba vinculado a esta entidad la represent\u00f3 judicialmente en el proceso de aval\u00fao de servidumbre petrolera objeto de la solicitud de tutela. Solicit\u00f3 que se accediera a las pretensiones de la tutela por cuanto el Juzgado Primero incurri\u00f3 en una v\u00eda de hecho en la medida que (i) \u201cdesatendi\u00f3 caprichosamente el mandato del art\u00edculo 317 del C.G.P para decretar el desistimiento t\u00e1cito\u201d y (ii) \u201cdesconoci\u00f3 caprichosamente los precedentes jurisprudenciales contenidos en las sentencias T-348 de 1998\u201d de la Corte Constitucional y la sentencia del 3 de febrero de 1998 de la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia.<\/p>\n<p>26. Contestaci\u00f3n del abogado Helman Jos\u00e9 Hern\u00e1ndez L\u00f3pez, qui\u00e9n representaba a los se\u00f1ores Ra\u00fal Ariza Santoyo y \u00c1ngela Consuelo Castro Castro en el proceso de servidumbre petrolera. Se\u00f1al\u00f3 que en esta oportunidad contestaba la tutela en calidad de agente oficioso de estas personas, y que la tutela no era procedente toda vez que pretend\u00eda reabrir un debate procesal que hab\u00eda concluido de manera legal y con observancia de los derechos fundamentales de las partes.<\/p>\n<p>27. Contestaci\u00f3n de Zurella Rojas Molina, designada por el despacho como curadora ad litem de los se\u00f1ores Ra\u00fal Ariza Santoyo y \u00c1ngela Consuelo Castro Castro, a quienes no fue posible notificar personalmente de la tutela. Sostuvo que el Juzgado accionado vulner\u00f3 el derecho al acceso a la administraci\u00f3n de justicia del accionante, en la medida que desconoci\u00f3 el poder especial otorgado oportuna y legalmente por Cenit al apoderado, y tambi\u00e9n vulner\u00f3 su derecho al debido proceso toda vez no aplic\u00f3 en debida forma el art\u00edculo 317 del C\u00f3digo General del Proceso, que establece la figura del desistimiento t\u00e1cito.<\/p>\n<p>28. Sentencia de primera instancia. El 20 de febrero de 2023, el Juzgado Quinto Civil del Circuito de Villavicencio decidi\u00f3 amparar los derechos del accionante y dejar sin efecto el auto del 23 de octubre de 2020, que decretaba la terminaci\u00f3n anticipada del proceso de aval\u00fao de servidumbre petrolera por el desistimiento t\u00e1cito. Lo anterior, al considerar que el Juzgado Primero incurri\u00f3 en un defecto procedimental en la medida que (i) pas\u00f3 por alto los memoriales y documentos allegados al expediente por parte del accionante; (ii) se neg\u00f3 a tramitar los recursos interpuestos en contra del auto del 23 de octubre de 2020, especialmente el recurso de apelaci\u00f3n, \u201cargumentando la ausencia \u00edntegra de poder del abogado, sin hacer uso del art\u00edculo 137 del C.G.P. y as\u00ed garantizar el derecho fundamental de la compa\u00f1\u00eda accionante a la tutela jurisdiccional efectiva\u201d; y (iii) aplic\u00f3 erradamente el art\u00edculo 317 del C\u00f3digo General del Proceso, que establece la figura del desistimiento t\u00e1cito, pues \u201cla actuaci\u00f3n procesal no se encontraba quieta o detenida por un acto procesal que correspondiere a la parte.\u201d<\/p>\n<p>29. Advirti\u00f3 que la postura del Juzgado accionado de hacer caso omiso a los escritos o solicitudes del accionante, bajo el entendimiento de que el otorgante del poder no hab\u00eda acreditado la calidad en la que actuaba, no ten\u00eda sustento en ninguna norma del ordenamiento jur\u00eddico. M\u00e1xime cuando el \u201cC\u00f3digo General del Proceso prev\u00e9 \u201cremedios\u201d para subsanar una indebida representaci\u00f3n de una parte y as\u00ed continuar con el tr\u00e1mite procesal respectivo.\u201d Al respecto, sostuvo que el numeral 4 del art\u00edculo 133 del C\u00f3digo General del Proceso establece como causal de nulidad \u201ccuando es indebida la representaci\u00f3n de alguna de las partes, o cuando quien act\u00faa como su apoderado judicial carece \u00edntegramente de poder\u201d; y que el inciso 5 del art\u00edculo 134 dispone que la nulidad por indebida representaci\u00f3n solo beneficiar\u00e1 a quien la haya invocado, por lo que constituye un acto de parte. Indic\u00f3 tambi\u00e9n que el art\u00edculo 137 del C\u00f3digo General del Proceso se\u00f1ala (i) que en cualquier estado del proceso el juez ordenar\u00e1 poner en conocimiento de la parte afectada las nulidades que no hayan sido saneadas, entre ellas, las que se generan por indebida representaci\u00f3n; (ii) que una vez advertida este tipo de nulidad por el despacho deber\u00e1 notificarla personalmente a la parte afectada y (iii) que si dentro de los tres (3) d\u00edas siguientes al de la notificaci\u00f3n dicha parte no alega la nulidad, esta quedar\u00e1 saneada y el proceso continuar\u00e1 su curso; y en caso contrario el juez la declarar\u00e1. A juicio del juzgado de instancia, el despacho accionado pudo advertir esta nulidad, notificarla al accionante, y asumir una postura menos restrictiva de su derecho al debido proceso.<\/p>\n<p>30. Impugnaci\u00f3n. El 23 de febrero de 2023, Helman Jos\u00e9 Hern\u00e1ndez L\u00f3pez, en representaci\u00f3n de Ra\u00fal Ariza Santoyo, present\u00f3 una solicitud de impugnaci\u00f3n en contra la sentencia de primera instancia, al reiterar que la acci\u00f3n de tutela no cumpli\u00f3 con los requisitos legales de procedibilidad, sino que, por el contrario, reabri\u00f3 el debate legal concluido, usando la acci\u00f3n de tutela como una tercera instancia.<\/p>\n<p>31. Sentencia de segunda instancia. El 28 de marzo de 2023, el Tribunal Superior del Distrito Judicial de Villavicencio revoc\u00f3 la sentencia de primera instancia y, en su lugar, neg\u00f3 el amparo solicitado al concluir que no se cumpli\u00f3 con el requisito general de inmediatez pues \u201cdesde el hecho verdaderamente generador de la presunta vulneraci\u00f3n alegada y la presentaci\u00f3n de esta s\u00faplica ha transcurrido casi tres (3) a\u00f1os, resultando improcedente este mecanismo de protecci\u00f3n cuando el paso del tiempo es significativo que resulta irrazonable y desproporcionado un control constitucional en la medida que la necesidad de amparo constitucional queda en entredicho.\u201d As\u00ed, sostuvo que \u201cla presunta vulneraci\u00f3n del derecho fundamental a un debido proceso data de veintiocho (28) de febrero de dos mil veinte (2020), oportunidad donde el Juzgado Primero Civil Municipal de Villavicencio se abstuvo de considerar los documentos aportados por el abogado Jhorman Alexis \u00c1lvarez Fierro.\u201d<\/p>\n<p>32. Indic\u00f3 tambi\u00e9n que es razonable que un Juez, en el marco de un proceso judicial, exija prueba de que la persona que otorga el poder es aquella a quien la persona jur\u00eddica invisti\u00f3 de poder general para representar sus intereses. As\u00ed, en su entendimiento, este deber no es una carga legal innecesaria pues su objetivo es generar seguridad en el operador judicial que tendr\u00e1 plena convicci\u00f3n de que la persona que est\u00e1 otorgando el poder verdaderamente se encuentre habilitada para hacerlo, \u201cluego el ius postulandi no se entiende acreditado incorporando a expediente un simple poder\u201d.<\/p>\n<p>4. Tr\u00e1mite en sede de revisi\u00f3n de tutela<\/p>\n<p>33. Mediante auto del 5 de octubre 2023, el despacho sustanciador profiri\u00f3 un auto de pruebas en el cual requiri\u00f3 al Juzgado Primero Civil Municipal de Villavicencio que remitiera copia \u00edntegra del expediente judicial radicado bajo el n\u00famero 500014003001 2013 00093 00, en el que se encuentran identificados como parte demandante a Cenit Transporte y Log\u00edstica de Hidrocarburos S.A.S y como demandados a Ra\u00fal Ariza Santoyo y \u00c1ngela Consuelo Castro Castro.<\/p>\n<p>34. El 10 de octubre de 2023, se recibi\u00f3 respuesta por parte del Juzgado Primero, qui\u00e9n remiti\u00f3 un enlace electr\u00f3nico que conten\u00eda el expediente digital del proceso de aval\u00fao de servidumbre petrolera objeto de la acci\u00f3n de tutela.<\/p>\n<p>35. El 25 de octubre de 2023, el accionante present\u00f3 al despacho sustanciador una solicitud de medida provisional, consistente en la suspensi\u00f3n del cumplimiento del numeral segundo del auto de 3 de mayo de 2023, proferido por el Juzgado Primero Civil Municipal de Villavicencio, dentro del tr\u00e1mite del proceso de Aval\u00fao de Servidumbre Petrolera, que accede a la solicitud de levantamiento de la medida cautelar de inscripci\u00f3n de la demanda en el folio de matr\u00edcula del bien objeto del proceso. Advirti\u00f3 el accionante que, de acuerdo con lo previsto en el art\u00edculo 591 del C.G.P., la inscripci\u00f3n de la demanda en este caso se tornaba indispensable, \u201cya que con ella se pueden vincular al tr\u00e1mite de instancia a terceros que con posterioridad al registro adquieran el inmueble o constituyan grav\u00e1menes sobre el predio\u201d. As\u00ed, sostuvo que \u201cla inscripci\u00f3n de la demanda les permite tener conocimiento de la situaci\u00f3n jur\u00eddica real y actual del bien, y, en caso de realizar cualquier acto, lo hacen a sabiendas que se encuentra bajo el tr\u00e1mite del proceso de Aval\u00fao de Servidumbre Petrolera, pendiente por definir, lo cual permite que, en caso de proferirse sentencia de fondo aquellos terceros se someten a lo decidido en dicho fallo, debido a que sus efectos los cobija con fuerza de cosa juzgada, tal como lo dispone el inciso tercero del art\u00edculo 303 del C.G.P.\u201d<\/p>\n<p>36. Se\u00f1al\u00f3 que si se levantaba la medida de inscripci\u00f3n de la demanda no es posible defender el derecho de servidumbre legal de hidrocarburos y sus efectos legales frente a terceros que inscriban actos en el Folio de Matr\u00edcula del predio objeto de gravamen, ni vincularlos dentro del tr\u00e1mite como causahabientes en caso de proferirse sentencia de fondo, y, en consecuencia, no quedan sujetos a los efectos de cosa juzgada. Finalmente, indic\u00f3 que la medida cautelar de inscripci\u00f3n de la demanda no afecta a la actual propietaria del predio, ni a quienes tienen otras medidas cautelares o grav\u00e1menes inscritos, pues la inscripci\u00f3n de la demanda se encuentra establecida por disposici\u00f3n legal, y \u00e9sta no limita el derecho de disposici\u00f3n que tiene el titular del domino sobre el bien.<\/p>\n<p>37. Mediante Auto 3158 del 13 de diciembre de 2023, la Sala de Revisi\u00f3n declar\u00f3 fundado el impedimento presentado el 6 de diciembre de 2023 por la magistrada Paola Andrea Meneses para decidir sobre la revisi\u00f3n de este expediente y la separ\u00f3 del estudio del mismo, toda vez que se configur\u00f3 la causal 1 del art\u00edculo 56 del C\u00f3digo de Procedimiento Penal.<\/p>\n<p>38. A trav\u00e9s de Auto 3159 del 15 de diciembre de 2023, la Sala de Revisi\u00f3n orden\u00f3 al Juzgado Primero la suspensi\u00f3n del cumplimiento y ejecuci\u00f3n de la orden contenida en el auto del 3 de mayo de 2023, que autoriza el levantamiento de la medida cautelar de inscripci\u00f3n de la demanda en el folio de matr\u00edcula del bien objeto del proceso de solicitud de aval\u00fao de servidumbre petrolera. Lo anterior, al advertir que ante la eventualidad de que, con el levantamiento de la inscripci\u00f3n de la demanda, la sentencia definitiva del proceso de servidumbre no sea oponible a los terceros que hubieran realizado operaciones sobre el predio entre el momento del levantamiento de la medida y el registro de la sentencia, se podr\u00eda generar una seria afectaci\u00f3n al debido proceso del demandante y los terceros con inter\u00e9s en el predio.<\/p>\n<p>. CONSIDERACIONES DE LA CORTE CONSTITUCIONAL<\/p>\n<p>Competencia<\/p>\n<p>39. Esta Sala de Revisi\u00f3n es competente para examinar las sentencias proferidas dentro del proceso de la referencia, de conformidad con lo previsto por los art\u00edculos 86 y 241.9 de la Constituci\u00f3n Pol\u00edtica y por los art\u00edculos 31 a 36 del Decreto 2591 de 1991.<\/p>\n<p>2. Problema jur\u00eddico y estructura de la decisi\u00f3n<\/p>\n<p>40. De acuerdo con la situaci\u00f3n f\u00e1ctica expuesta y las decisiones de instancia mencionadas, le corresponde a la Sala de Revisi\u00f3n determinar si, como lo estableci\u00f3 el Tribunal Superior del Distrito Judicial de Villavicencio, la solicitud de tutela es improcedente porque no se cumpli\u00f3 con el requisito de inmediatez, o si, por el contrario, el Juzgado Primero Civil Municipal de Villavicencio, a trav\u00e9s del auto de 23 de octubre de 2020, dictado dentro del proceso de solicitud de aval\u00fao por imposici\u00f3n de servidumbre petrolera promovido por el accionante, incurri\u00f3 en una serie de defectos procedimentales, por (i) no reconocer al abogado Jhorman Alexis \u00c1lvarez Fierro como apoderado judicial de la empresa Cenit; (ii) terminar anticipadamente el proceso de aval\u00fao de servidumbre petrolera bajo la figura del desistimiento t\u00e1cito; y (iii) no tramitar el recurso de apelaci\u00f3n interpuesto por el accionante en contra el auto que declar\u00f3 el desistimiento t\u00e1cito.<\/p>\n<p>41. Para resolver el problema jur\u00eddico planteado, se analizar\u00e1 la procedencia excepcional de la acci\u00f3n de tutela contra providencia judicial en el caso sub examine (3). Posteriormente, se estudiar\u00e1 la representaci\u00f3n de las personas jur\u00eddicas en los procesos judiciales a partir de su regulaci\u00f3n constitucional y legal y, particularmente, el alcance que tienen los poderes especiales (4). Luego se analizar\u00e1 la naturaleza de la figura del desistimiento t\u00e1cito como una forma de terminar anticipadamente un proceso judicial (5). Y finalmente, se resolver\u00e1 el caso concreto (6).<\/p>\n<p>3. Procedencia excepcional de la acci\u00f3n de tutela contra providencia judicial. Reiteraci\u00f3n jurisprudencial \u2013 verificaci\u00f3n de su cumplimiento<\/p>\n<p>42. De acuerdo con el art\u00edculo 86 de la Constituci\u00f3n, toda persona puede reclamar ante los jueces, mediante la acci\u00f3n de tutela, la protecci\u00f3n inmediata de sus derechos constitucionales fundamentales vulnerados o amenazados por la acci\u00f3n o la omisi\u00f3n de cualquier autoridad p\u00fablica o, en los casos que establezca la ley, de los particulares, cuando el afectado no disponga de otro medio de defensa judicial, salvo que aquella se utilice como mecanismo transitorio para evitar un perjuicio irremediable.<\/p>\n<p>43. Como se dijo, este mecanismo de protecci\u00f3n procede contra cualquier autoridad que con sus actuaciones u omisiones vulnere o amenace derechos constitucionales fundamentales, incluidas, por supuesto, las autoridades judiciales, en cuanto autoridades de la Rep\u00fablica, las cuales, sin excepci\u00f3n, est\u00e1n instituidas para proteger a todas las personas residentes en Colombia, en su vida, honra, bienes, creencias y dem\u00e1s derechos y libertades, como lo dispone el art\u00edculo 2 de la Constituci\u00f3n.<\/p>\n<p>44. Bajo tales supuestos constitucionales y el art\u00edculo 6 del Decreto Ley 2591 de 1991, \u00a0la Corte Constitucional ha admitido la procedencia excepcional de la acci\u00f3n de tutela contra providencias judiciales, dada la naturaleza judicial de las citadas autoridades, puesto que en tales casos \u201cla adecuada protecci\u00f3n de los principios y valores constitucionales implica un ejercicio de ponderaci\u00f3n entre la eficacia de la mencionada acci\u00f3n \u2013presupuesto del Estado Social y Democr\u00e1tico de Derecho\u2013, y la vigencia de la autonom\u00eda e independencia judicial, el principio de cosa juzgada y la seguridad jur\u00eddica\u201d.<\/p>\n<p>45. La excepcionalidad de la tutela contra providencias judiciales ha llevado a la Corte, a partir de la Sentencia C-590 de 2005, a exigir el cumplimiento de un conjunto de requisitos generales y espec\u00edficos de procedencia, que a continuaci\u00f3n se analizar\u00e1n para el caso concreto.<\/p>\n<p>1. %1.1 \u00a0Requisitos generales de procedencia<\/p>\n<p>46. Legitimaci\u00f3n. De lo dispuesto en los art\u00edculos 86 de la Constituci\u00f3n y 10 del Decreto 2591 de 1991, la jurisprudencia constitucional ha interpretado que la titularidad del derecho fundamental presuntamente afectado, amenazado o vulnerado, determina el inter\u00e9s directo del accionante en su protecci\u00f3n y, por tanto, la legitimidad por activa en el proceso de tutela. Esta exigencia \u201cbusca garantizar que la persona que acude a la acci\u00f3n de tutela tenga un inter\u00e9s directo y particular respecto de la solicitud de amparo que eleva ante el juez constitucional, de manera que pueda establecerse sin dificultad, que lo reclamado es la protecci\u00f3n de un derecho fundamental del propio demandante y no de otro\u201d.<\/p>\n<p>47. En relaci\u00f3n con la legitimaci\u00f3n en la causa por activa, este requisito se acredita en el caso concreto, dado que la acci\u00f3n de tutela fue presentada por David Arce Rojas, en representaci\u00f3n judicial de la empresa Cenit, quien considera que el despacho accionado vulner\u00f3 sus derechos fundamentales al debido proceso, tutela judicial efectiva y acceso a la administraci\u00f3n de justicia, al decretar el desistimiento t\u00e1cito en un proceso de solicitud de aval\u00fao de servidumbre petrolera. En este caso se cumple tambi\u00e9n la legitimaci\u00f3n por pasiva toda vez que el Juzgado Primero Civil Municipal de Villavicencio es la\u00a0autoridad que profiri\u00f3 la decisi\u00f3n a la cual se le atribuye la vulneraci\u00f3n de los derechos fundamentales.<\/p>\n<p>48. Subsidiariedad. En atenci\u00f3n a su car\u00e1cter subsidiario, la acci\u00f3n de tutela es improcedente si existen otros recursos o medios de defensa judiciales \u201cid\u00f3neos y eficaces\u201d, \u201catendiendo las circunstancias en que se encuentra el solicitante\u201d (art\u00edculo 6.1 Decreto 2591 de 1991), salvo que \u201cse utilice como mecanismo transitorio para evitar un perjuicio irremediable\u201d (art\u00edculo 8 Decreto 2591 de 1991).<\/p>\n<p>49. En materia de tutela contra providencias judiciales, la exigencia de subsidiariedad adquiere un matiz especial al exigir una carga procesal razonable al accionante, de haber agotado los medios judiciales ordinarios y extraordinarios dispuestos por el Legislador para cuestionar los presuntos defectos que alega, siempre que los mismos hubiesen estado a su disposici\u00f3n o, trat\u00e1ndose de los recursos extraordinarios, siempre que sus causales se adecuen a lo cuestionado en tutela, salvo que se trate de un supuesto de perjuicio irremediable, circunstancias que deben valorarse en cada caso concreto.<\/p>\n<p>50. En el caso concreto, del an\u00e1lisis del expediente del proceso de servidumbre petrolera, se evidencia que el accionante present\u00f3 los siguientes recursos: (i) recurso de reposici\u00f3n y en subsidi\u00f3 apelaci\u00f3n contra el auto del 23 de octubre de 2020 que declar\u00f3 el desistimiento t\u00e1cito; (ii) recurso de reposici\u00f3n contra el auto del 4 de junio de 2021 que resolvi\u00f3 negativamente la reposici\u00f3n del auto del 23 de octubre de 2020 y neg\u00f3 la apelaci\u00f3n; (iii) recurso de reposici\u00f3n y en subsidio de queja contra el auto del 26 de agosto de 2021 que no dio tr\u00e1mite al recurso de reposici\u00f3n contra el auto del 4 de junio de 2021; e (iv) incidente de nulidad contra todo lo actuado a partir del 28 de febrero de 2020.<\/p>\n<p>51. En consecuencia, la Sala advierte que el accionante agot\u00f3 todos los recursos que ten\u00eda a su alcance para controvertir la providencia cuestionada. Por lo tanto, al no existir otro medio de defensa judicial, se considera satisfecho el requisito de subsidiariedad.<\/p>\n<p>52. Inmediatez. Esta exigencia implica acreditar que, atendiendo a la vulneraci\u00f3n alegada y a las circunstancias del accionante, la tutela se interpuso en un t\u00e9rmino razonable a partir del hecho que origin\u00f3 la vulneraci\u00f3n. Por tanto, el an\u00e1lisis de su cumplimiento debe realizarse a la luz del principio de razonabilidad de conformidad con lo dispuesto en el art\u00edculo 86 de la Constituci\u00f3n en cuanto establece que, si bien esta acci\u00f3n puede ejercerse \u201cen todo momento\u201d, est\u00e1 establecida para reclamar la \u201cprotecci\u00f3n inmediata\u201d de los derechos fundamentales. Por tanto, a pesar de no existir un t\u00e9rmino de caducidad para esta acci\u00f3n, es necesario acreditar que el tiempo transcurrido entre la presunta lesi\u00f3n del derecho y la interposici\u00f3n de la acci\u00f3n corresponda a un plazo razonable, atendiendo a las circunstancias del caso.<\/p>\n<p>53. En el caso que se analiza, se observa que la \u00faltima decisi\u00f3n proferida por el Juzgado accionado fue el 26 de octubre de 2022, como respuesta a un recurso de reposici\u00f3n y en subsidio queja, as\u00ed como una solicitud de nulidad presentada por el accionante. Tambi\u00e9n se advierte que la solicitud de tutela fue radicada por el accionante el 7 de febrero de 2023, es decir, casi cuatro meses despu\u00e9s de la \u00faltima providencia emitida por el despacho accionado.<\/p>\n<p>54. Al respecto, la Sala considera que el tiempo transcurrido entre las decisiones que originaron el presente tr\u00e1mite y la interposici\u00f3n de la acci\u00f3n de tutela es razonable, en la medida que el accionante primero agot\u00f3 todos los recursos ordinarios y extraordinarios que ten\u00eda a su alcance para discutir la decisi\u00f3n atacada, y despu\u00e9s de obtener el \u00faltimo pronunciamiento del Juzgado, decidi\u00f3 interponer la solicitud de amparo. Por el contrario, no es acertada la interpretaci\u00f3n que realiz\u00f3 el Tribunal Superior del Distrito Judicial de Villavicencio, en cuanto a que la solicitud de tutela es improcedente porque no se cumpli\u00f3 con el requisito de inmediatez, dado que desde el hecho generador de la presunta vulneraci\u00f3n alegada (los autos de 28 de febrero y 23 de octubre de 2020) y la presentaci\u00f3n de esta s\u00faplica han transcurrido casi tres (3) a\u00f1os. Aceptar tal apreciaci\u00f3n supondr\u00eda desnaturalizar el car\u00e1cter subsidiario y residual de la acci\u00f3n de tutela y, adem\u00e1s, presumir que el accionante interpuso una serie de recursos solo con la finalidad de dilatar la resoluci\u00f3n de la controversia y el eventual uso de la solicitud de amparo, y no con el objetivo leg\u00edtimo de obtener la defensa de sus intereses ante el juez natural. Por lo tanto, la Sala entiende cumplido el requisito de inmediatez en el caso concreto.<\/p>\n<p><\/p>\n<p>55. Relevancia constitucional. La tutela debe involucrar la posible vulneraci\u00f3n de derechos fundamentales del accionante. De acuerdo con la jurisprudencia constitucional, no resulta suficiente la sola alusi\u00f3n a la vulneraci\u00f3n de un derecho fundamental, pues este requisito busca cumplir adem\u00e1s tres finalidades:\u00a0preservar la competencia e independencia de los jueces y, de esa manera, evitar que la tutela se utilice para discutir asuntos de mera legalidad;\u00a0restringir el ejercicio de esta acci\u00f3n a cuestiones de relevancia constitucional que afecten derechos fundamentales, e\u00a0impedir que se convierta en una instancia o recurso adicional para controvertir las decisiones de los jueces. Para el efecto, conforme a la reiterada jurisprudencia de esta corporaci\u00f3n, son tres los criterios de an\u00e1lisis para establecer si una tutela tiene relevancia constitucional:\u00a0(i) la controversia debe versar sobre un asunto constitucional y no meramente legal y\/o econ\u00f3mico; (ii) el caso debe involucrar alg\u00fan debate jur\u00eddico que gire en torno al contenido, alcance y goce de alg\u00fan derecho fundamental; y, (iii) la tutela no es una instancia o recurso adicional para reabrir debates meramente legales.<\/p>\n<p>56. Para la Sala, el caso bajo estudio reviste de relevancia constitucional pues el debate gira en torno a la presunta vulneraci\u00f3n de los derechos fundamentales al debido proceso, tutela judicial efectiva y acceso a la administraci\u00f3n de justicia, como consecuencia de una aplicaci\u00f3n particular de la autoridad judicial de las normas procesales que regulan la representaci\u00f3n de las personas jur\u00eddicas en los procesos judiciales y la terminaci\u00f3n anticipada de un proceso de servidumbre petrolera por la aplicaci\u00f3n del desistimiento t\u00e1cito. As\u00ed, se tratar\u00eda de una posible aplicaci\u00f3n restrictiva de normas procedimentales que obstaculizar\u00edan la eficacia del derecho sustancial y que, por tanto, podr\u00edan constituir actuaciones que devienen en una denegaci\u00f3n importante del debido proceso y el acceso a la justicia.<\/p>\n<p>58. Cuando se trate de una irregularidad procesal, que esta tenga incidencia\u00a0en la decisi\u00f3n que se considera lesiva de los derechos fundamentales. En el caso concreto, la Sala considera que las irregularidades procesales que alega el accionante pudieron tener incidencia en la decisi\u00f3n que vulner\u00f3 supuestamente sus derechos fundamentales al debido proceso, tutela judicial efectiva y acceso a la administraci\u00f3n de justicia, por cuanto presuntamente tuvieron como resultado el no reconocimiento de las actuaciones adelantadas por el apoderado de la empresa Cenit en el proceso, y la consecuente terminaci\u00f3n anticipada del mismo por desistimiento t\u00e1cito.<\/p>\n<p>59. Que no se trate de una acci\u00f3n de tutela contra un fallo de tutela, salvo si existi\u00f3 fraude en su adopci\u00f3n. En el caso concreto la decisi\u00f3n atacada no es un fallo de tutela, sino una providencia emitida en un proceso de aval\u00fao por imposici\u00f3n de servidumbre petrolera.<\/p>\n<p>2.2 \u00a0Requisitos espec\u00edficos de procedencia.<\/p>\n<p>60. Adem\u00e1s de los anteriores requisitos generales, es necesario acreditar que la autoridad judicial demandada vulner\u00f3 de forma grave el derecho al debido proceso del accionante, a tal punto que la decisi\u00f3n judicial resulta incompatible con la Constituci\u00f3n por incurrir en alguno de los siguientes defectos que la jurisprudencia constitucional denomina requisitos espec\u00edficos de procedibilidad: (i)\u00a0defecto org\u00e1nico, (ii)\u00a0defecto procedimental, (iii)\u00a0defecto f\u00e1ctico, (iv)\u00a0defecto material o sustantivo, (v)\u00a0error inducido, (vi)\u00a0falta de motivaci\u00f3n, (vii)\u00a0desconocimiento del precedente y (viii)\u00a0violaci\u00f3n directa de la Constituci\u00f3n.<\/p>\n<p>61. En efecto, como se describi\u00f3 en los p\u00e1rrafos 21 y 22 supra, el accionante alega que el Juzgado Primero Civil Municipal de Villavicencio incurri\u00f3 en un defecto procedimental absoluto al decretar el 23 de octubre de 2020 el desistimiento t\u00e1cito del proceso de solicitud de aval\u00fao de servidumbre petrolera.<\/p>\n<p>3 Representaci\u00f3n de las personas jur\u00eddicas en los procesos judiciales a partir de su regulaci\u00f3n constitucional y legal<\/p>\n<p>62. Derecho al debido proceso y principio de prevalencia de lo sustancial sobre lo formal en la aplicaci\u00f3n de normas procesales. De acuerdo con el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica, el derecho al debido proceso tiene como prop\u00f3sito proteger las garant\u00edas b\u00e1sicas o esenciales de los procesos administrativos, sancionatorios y judiciales, a fin de resguardar a los ciudadanos de \u201clos abusos o desviaciones de poder por parte de las autoridades, originadas no solo de las actuaciones procesales sino de las decisiones que se adopten y puedan afectar injustamente los derechos e intereses leg\u00edtimos de aquellos\u201d. As\u00ed mismo, la Corte Constitucional ha se\u00f1alado que el debido proceso tiene como finalidad la defensa y preservaci\u00f3n del valor material de la justicia, y que este derecho se materializa con la observaci\u00f3n de las formas procesales.<\/p>\n<p>63. En relaci\u00f3n con los procesos judiciales, esta Corporaci\u00f3n ha advertido tambi\u00e9n que las normas procesales \u201cse encuentran previstas para materializar los derechos de las partes en el marco de los procesos judiciales, que constituyen el fin \u00faltimo del derecho adjetivo\u201d, de modo que estas normas \u201cdeben interpretarse a la luz de los principios de acceso efectivo a la administraci\u00f3n de justicia (art. 229 ibidem) y prevalencia del derecho sustancial (art. 228 ibidem).\u201d De hecho, el C\u00f3digo General del Proceso desarroll\u00f3 el principio constitucional de prevalencia de lo sustancial sobre lo formal en sus art\u00edculos 11 y 12, que establecen las siguientes reglas interpretativas de las normas procesales: (i) la efectividad de los derechos reconocidos por la ley sustancial; (ii) la aplicaci\u00f3n de los principios constitucionales y generales del derecho procesal garantizando en todo caso el debido proceso, el derecho de defensa, la igualdad de las partes y los dem\u00e1s derechos constitucionales fundamentales; y (iii) la no exigencia de formalidades innecesarias.<\/p>\n<p>64. As\u00ed, la Corte ha reiterado que \u201csi bien las normas procesales han sido instituidas para garantizar el derecho al debido proceso, no pueden convertirse en un l\u00edmite infranqueable para la consecuci\u00f3n del derecho subjetivo en discusi\u00f3n. Por expresa disposici\u00f3n constitucional y legal, el principio de prevalencia de lo sustancial sobre lo formal es una norma rectora de la ley procesal, y de obligatoria observancia para las autoridades judiciales. De manera que, cuando un juez adopta una decisi\u00f3n que desconoce el citado principio, viola el derecho fundamental al debido proceso de la parte.\u201d<\/p>\n<p>65. Derecho a la defensa t\u00e9cnica y derecho de postulaci\u00f3n en los procesos judiciales. Por otro lado, la jurisprudencia constitucional ha entendido que el derecho a la defensa es una de las principales garant\u00edas del debido proceso, y la ha definido como la \u201coportunidad reconocida a toda persona, en el \u00e1mbito de cualquier proceso o actuaci\u00f3n judicial o administrativa, de ser o\u00edda, de hacer valer las propias razones y argumentos, de controvertir, contradecir y objetar las pruebas en contra y de solicitar la pr\u00e1ctica y evaluaci\u00f3n de las que se estiman favorables, as\u00ed como ejercitar los recursos que la otorga.\u201d As\u00ed, este derecho permite que los sujetos procesales, a trav\u00e9s de una asistencia t\u00e9cnica realizada por un abogado de confianza o uno designado por el Estado, puedan ser o\u00eddos y hacer valer sus argumentos y pruebas en el curso de un proceso que los afecta.<\/p>\n<p>66. En similar sentido, el art\u00edculo 229 de la Constituci\u00f3n establece que toda persona tiene derecho a acceder a la administraci\u00f3n de justicia y que, en ciertos procesos, el derecho a la defensa debe ser ejercido mediante un apoderado judicial, conforme al derecho de postulaci\u00f3n. El apoderamiento judicial se otorga a trav\u00e9s de \u201cun contrato de mandato en el cual una parte designa al abogado para el proceso y lo representa, mediante un poder general o especial\u201d, de acuerdo con lo establecido en la Secci\u00f3n Segunda, Cap\u00edtulo Cuarto del C\u00f3digo General del Proceso (art\u00edculo 73 en adelante). Esta Corporaci\u00f3n ha definido el derecho de postulaci\u00f3n como \u201cel derecho que se tiene para actuar en los procesos, como profesional del derecho, bien sea personalmente en causa propia o como apoderado de otra persona.\u201d<\/p>\n<p>67. Representaci\u00f3n de las personas jur\u00eddicas en procesos judiciales. En cuanto a la intervenci\u00f3n de las personas jur\u00eddicas en un proceso judicial, el C\u00f3digo General del Proceso establece que pueden comparecer por medio de sus representantes legales o apoderados generales debidamente inscritos (Art\u00edculos 53 y 54) o a trav\u00e9s de un abogado legalmente autorizado (Art\u00edculo 73). Dicha autorizaci\u00f3n legal se realiza a trav\u00e9s de un poder especial (i) constituido en un documento privado, (ii) conferido verbalmente en audiencia, o por memorial dirigido al juez de conocimiento; y (iii) con los asuntos debidamente identificados sobre los que versa la representaci\u00f3n. Para efectos judiciales, el poder especial deber\u00e1 ser presentado personalmente por el poderdante ante un juez, oficina judicial de apoyo o un notario (Art\u00edculo 74).<\/p>\n<p>68. Respecto a la presentaci\u00f3n personal del poder especial ante un notario, el Decreto 1069 de 2015 establece que \u201cla fe p\u00fablica o notarial otorga plena autenticidad a las declaraciones emitidas ante el notario y a lo expresado por \u00e9ste respecto de los hechos percibidos en el ejercicio de sus funciones, en los casos y con los requisitos que la ley establece\u201d. As\u00ed mismo, el Decreto 960 de 1970 se\u00f1ala que los notarios pueden dar testimonio de que \u201cla firma puesta en un documento corresponde a la de la persona que la haya registrado ante \u00e9l, previa confrontaci\u00f3n de las dos.\u201d En similar sentido, el art\u00edculo 244 del C\u00f3digo General del Proceso dispone que \u201clos documentos p\u00fablicos y los privados emanados de las partes o de terceros, en original o en copia, elaborados, firmados o manuscritos, y los que contengan la reproducci\u00f3n de la voz o de la imagen, se presumen aut\u00e9nticos, mientras no hayan sido tachados de falso o desconocidos, seg\u00fan el caso.\u201d<\/p>\n<p>69. Prueba de la existencia, representaci\u00f3n legal o calidad en la que act\u00faan las partes. El art\u00edculo 84 del C\u00f3digo General del proceso establece como anexo de la demanda la prueba de la existencia y representaci\u00f3n de las partes y de la calidad en la que intervendr\u00e1n en el proceso. El art\u00edculo 85, por su parte, dispone que \u201cla prueba de la existencia y representaci\u00f3n de las personas jur\u00eddicas de derecho privado s\u00f3lo podr\u00e1 exigirse cuando dicha informaci\u00f3n no conste en las bases de datos de las entidades p\u00fablicas y privadas que tengan a su cargo el deber de certificarla. Cuando la informaci\u00f3n est\u00e9 disponible por este medio, no ser\u00e1 necesario certificado alguno. En los dem\u00e1s casos, con la demanda se deber\u00e1 aportar la prueba de la existencia y representaci\u00f3n legal del demandante y del demandado.\u201d As\u00ed, de la lectura conjunta de ambas normas procesales, resulta claro que en los procesos judiciales donde alguna de las partes sea una persona jur\u00eddica, el Juez debe, primero, consultar su existencia y representaci\u00f3n en las bases de datos de las entidades que tienen a su cargo el deber de certificarla y, despu\u00e9s, y solo en el supuesto de que dicha informaci\u00f3n no est\u00e9 disponible en tales bases de datos, podr\u00e1 exigir este certificado a la parte.<\/p>\n<p>70. Al respecto, la Corte Suprema de Justicia ha reiterado en su jurisprudencia que en la actualidad el certificado de existencia y representaci\u00f3n legal no puede exigirse por el juez cuando se trate de personas jur\u00eddicas cuya informaci\u00f3n conste en las bases de datos de las entidades p\u00fablicas y privadas que tengan a su cargo el deber de certificarla, tal y como lo establece el art\u00edculo 85 del C\u00f3digo General del proceso, que enfatiza que \u201ccuando la informaci\u00f3n est\u00e9 disponible por este medio, no ser\u00e1 necesario certificado alguno.\u201d Igualmente, ha advertido que esta norma \u201catiende a los esfuerzos encaminados a procurar el uso de las tecnolog\u00edas de la informaci\u00f3n y de las comunicaciones al interior del proceso, de acuerdo lo dispuesto por el art\u00edculo 103 de la norma adjetiva civil, as\u00ed como la Ley 527 de 1999, que propenden porque en todas las actuaciones judiciales, se haga uso de las mismas.\u201d Tambi\u00e9n se\u00f1ala que, seg\u00fan el art\u00edculo 15 del Decreto 19 de 2012, \u201clas entidades p\u00fablicas y las privadas que cumplan funciones p\u00fablicas o presten servicios p\u00fablicos pueden conectarse gratuitamente a los registros p\u00fablicos que llevan las entidades encargadas de expedir los certificados de existencia y representaci\u00f3n legal de las personas jur\u00eddicas\u2026 en las condiciones y seguridades requeridas que establezca el reglamento. La lectura de la informaci\u00f3n obviar\u00e1 la solicitud del certificado y servir\u00e1 de prueba bajo la anotaci\u00f3n del funcionario que efect\u00fae la consulta\u201d.<\/p>\n<p>71. As\u00ed, los despachos judiciales del pa\u00eds pueden solicitar a la entidad encargada de expedir los certificados de existencia y representaci\u00f3n legal, CONFECAMARAS, que les permitan acceder a estos registros con el prop\u00f3sito de cumplir su funci\u00f3n. En estos casos, dicha entidad permitir\u00e1 el acceso gratuito e informar\u00e1 la forma c\u00f3mo los despachos deben ingresar. Seg\u00fan la Corte Suprema de Justicia, \u201cde acuerdo con lo consagrado en los art\u00edculos 85 y 103 del C\u00f3digo General, y teniendo en cuenta las posibilidades que tienen los funcionarios judiciales de \u00a0acudir a cualquiera de los medios antes referidos, no es dable que \u00e9stos, de manera autom\u00e1tica, exijan la prueba de existencia y representaci\u00f3n, e inadmitan por dicho requisito, sin que previamente hubiesen verificado que tal informaci\u00f3n no reposaba en ninguna de las bases de datos citadas o cualquier otra que repose en entidades encargadas de su certificaci\u00f3n lleven, porque ello traslada una carga a la parte que la misma Ley le ha quitado.\u201d<\/p>\n<p>72. Sobre este asunto, la Sala tambi\u00e9n advierte que la regla sobre la prueba de la existencia y representaci\u00f3n de las personas jur\u00eddicas fue introducida por el art\u00edculo 85 del C\u00f3digo General del Proceso, y por tanto esta regla no exist\u00eda bajo la vigencia del C\u00f3digo de Procedimiento Civil. De ah\u00ed que actualmente no puede sustentarse, como lo hace el juez ordinario en este caso, la exigencia del certificado, en la sentencia T-328 de 2002 de la Corte Constitucional, anterior a la vigencia del C\u00f3digo General del Proceso, en la que estableci\u00f3 que \u201cel juez que al momento de reconocer un nuevo apoderado dentro del proceso desee verificar que \u00e9ste ha obtenido poder del representante legal de la persona jur\u00eddica parte en el proceso, s\u00f3lo podr\u00e1 encontrar probada tal circunstancia en el certificado de existencia \u00a0y representaci\u00f3n legal de la entidad con el cual podr\u00e1 cotejar si quien otorga poder para actuar en el proceso es quien representa legalmente a la sociedad.\u201d Esta providencia se situaba bajo la vigencia del C\u00f3digo de Procedimiento Civil, y por tanto se\u00f1alaba que el Juez pod\u00eda exigir autom\u00e1ticamente en todos los casos el certificado de existencia y representaci\u00f3n legal de las personas jur\u00eddicas que hac\u00edan parte del proceso.<\/p>\n<p>73. Este cambio que introdujo el C\u00f3digo General del Proceso, como lo ha expresado la Corte Constitucional frente a otros asuntos, se enmarca dentro del prop\u00f3sito del legislador de establecer un modelo procesal, por un lado, \u201cde car\u00e1cter dispositivo en el que el avance y resultas de la actividad dependa de la diligencia y actividad de las partes, as\u00ed como del cumplimiento de las cargas procesales que les impone la legislaci\u00f3n por acudir ante los jueces\u201d; y por otro lado, con una serie de \u201cfacultades procesales poderosas para que el juez, director del proceso, decrete de oficio la pr\u00e1ctica de pruebas en busca de determinar la verdad de los hechos que provocaron una demanda y garantice la igualdad de armas entre las partes y en ese contexto debe entenderse las disposiciones que regulan las pruebas.\u201d<\/p>\n<p>74. Incluso, ante la novedad de este asunto dispuesto en el art\u00edculo 85 del C\u00f3digo General del Proceso, en el a\u00f1o 2017 la Corte Suprema de Justicia exhort\u00f3 a la Sala Administrativa del Consejo Superior de la Judicatura a fin de que adoptara los mecanismos necesarios para instruir a los diferentes funcionarios judiciales respecto al uso y acceso a las bases de datos de las C\u00e1maras de Comercio, atendiendo la normatividad existente al respecto.<\/p>\n<p>4 El desistimiento t\u00e1cito como una forma de terminaci\u00f3n anticipada de un proceso judicial.<\/p>\n<p>75. El desistimiento t\u00e1cito, regulado en el art\u00edculo 317 del C\u00f3digo General del Proceso, constituye una forma de terminaci\u00f3n anormal del proceso, consecuencia de la falta de inter\u00e9s de quien demanda para continuar con el mismo. Esta figura se estructura, entonces, sobre la base de una presunci\u00f3n respecto de la negligencia, omisi\u00f3n, descuido o inactividad de la parte.<\/p>\n<p>76. El art\u00edculo 317 del C\u00f3digo General del Proceso establece dos modalidades de desistimiento t\u00e1cito: la que regula el numeral 1, que opera en aquellos casos en los que la parte guarda silencio frente a un requerimiento realizado por el juez para impulsar el proceso. En este caso, el juez ordena a la parte el cumplimiento de esta carga procesal dentro de los treinta (30) d\u00edas siguientes mediante providencia que se notifica por estado. Vencido dicho t\u00e9rmino sin que se haya promovido el tr\u00e1mite respectivo, el juez tendr\u00e1 por desistida t\u00e1citamente la respectiva actuaci\u00f3n y as\u00ed lo declarar\u00e1 en providencia en la que adem\u00e1s impondr\u00e1 condena en costas.<\/p>\n<p>77. La segunda modalidad (numeral 2) se materializa en los eventos en los que el proceso se encuentra inactivo por el t\u00e9rmino m\u00ednimo de 1 a\u00f1o, o excepcionalmente de 2 a\u00f1os. Esta modalidad de desistimiento se decretar\u00e1 a petici\u00f3n de parte o de oficio y sin necesidad de requerimiento previo. Pese a que ambos tipos de desistimiento t\u00e1cito comparten la misma consecuencia procesal, esto es, la terminaci\u00f3n anticipada del proceso, en los casos en los que el proceso se encuentra inactivo por 1 o 2 a\u00f1os, es decir la modalidad que establece el numeral 2 del art\u00edculo 317, se presenta una consecuencia adicional, que es la extinci\u00f3n del derecho objeto de litigio, siempre que se acrediten los requisitos para tal fin.<\/p>\n<p>78. La providencia que decreta el desistimiento t\u00e1cito se debe notificar por estado y es susceptible del recurso de apelaci\u00f3n. Este recurso, adem\u00e1s, se concede en el efecto suspensivo, lo que implica, entre otras cosas, que se suspende el cumplimiento de la decisi\u00f3n hasta tanto se resuelve el recurso (Literal e, Art\u00edculo 317 del C\u00f3digo General del Proceso).<\/p>\n<p>79. Seg\u00fan la jurisprudencia constitucional, \u201cel desistimiento t\u00e1cito, adem\u00e1s de ser entendido como una sanci\u00f3n procesal que se configura ante el incumplimiento de las cargas procesales del demandante, opera como garante de: (i) el derecho de todas las personas a acceder a una administraci\u00f3n de justicia diligente, c\u00e9lere, eficaz y eficiente; (ii) la posibilidad de obtener pronta y cumplida justicia y (ii) el acceso material a la justicia, en favor de quienes conf\u00edan al Estado la soluci\u00f3n de sus conflictos. Todo esto en el entendido de que la racionalizaci\u00f3n del trabajo judicial y la descongesti\u00f3n del aparato jurisdiccional, finalidades a las que aporta la decisi\u00f3n de terminar anticipadamente un tr\u00e1mite judicial, contribuyen significativamente a hacer m\u00e1s expedito el tr\u00e1mite de los litigios judiciales.\u201d<\/p>\n<p>80. El inciso segundo del art\u00edculo 2 del C\u00f3digo General del Proceso se\u00f1ala que los jueces tienen el deber de impulsar los procesos y evitar demoras injustificadas. En este sentido, el Juez deber\u00e1 declarar el desistimiento t\u00e1cito en los casos que (i) la carga sea impuesta a la parte procesal que promovi\u00f3 el tr\u00e1mite, de modo que no opera si la actividad est\u00e1 a cargo del Juez o de la contraparte; y (ii) el cumplimiento de dicha carga procesal sea indispensable para continuar con el tr\u00e1mite.<\/p>\n<p>81. Esta figura es aplicable, en principio, a todos los procesos judiciales. S\u00f3lo en algunos procesos, como los de liquidaci\u00f3n de sociedades conyugales y patrimoniales, as\u00ed como los que involucran el estado civil de las personas y los alimentos, la Corte Suprema de Justicia ha considerado que el desistimiento t\u00e1cito no es aplicable.<\/p>\n<p>5 An\u00e1lisis del caso concreto.<\/p>\n<p>82. Vista la regulaci\u00f3n constitucional y legal de la representaci\u00f3n de las personas jur\u00eddicas en los procesos judiciales, particularmente, el alcance que tienen los poderes especiales, as\u00ed como la naturaleza de la figura del desistimiento t\u00e1cito, le corresponde a la Sala resolver, a la luz de estas consideraciones, si el Juzgado Primero Civil Municipal de Villavicencio incurri\u00f3 en los tres defectos procedimentales alegados por el accionante, a saber: (i) no reconocer al abogado Jhorman Alexis \u00c1lvarez Fierro como apoderado judicial de la empresa Cenit; (ii) terminar anticipadamente el proceso de aval\u00fao de servidumbre petrolera bajo la figura del desistimiento t\u00e1cito sin cumplir con los requisitos de ley; y (iii) negar el tr\u00e1mite del recurso de apelaci\u00f3n interpuesto por el accionante contra el auto que declar\u00f3 el desistimiento t\u00e1cito.<\/p>\n<p>83. Primer defecto procedimental. Negativa de reconocimiento del apoderado. Frente al hecho de que el juez civil no reconoci\u00f3 al \u00a0abogado Jhorman Alexis \u00c1lvarez Fierro como apoderado judicial de la empresa Cenit y, en consecuencia, no dio validez a sus actuaciones en el proceso, la Sala considera que el Juzgado Primero Civil Municipal de Villavicencio incurri\u00f3 en un defecto procedimental, toda vez que desconoci\u00f3 el tr\u00e1mite procesal dispuesto legal y constitucionalmente para el reconocimiento de los poderes especiales presentados ante notarios p\u00fablicos en el marco de un proceso judicial.<\/p>\n<p>84. En efecto, en virtud de lo dispuesto en los art\u00edculos 73 y siguientes del C\u00f3digo General del Proceso, el Juzgado accionado debi\u00f3 analizar \u00edntegramente el poder allegado al proceso el 14 de febrero de 2019 por la empresa Cenit, en particular en cuanto dicho poder especial (i) se constituy\u00f3 en un documento privado, (ii) fue conferido en un memorial dirigido al juez de conocimiento, (iii) establec\u00eda claramente los asuntos en los que versaba la representaci\u00f3n, y (iv) fue presentado personalmente ante un notario p\u00fablico. Adicionalmente, el despacho accionado debi\u00f3 tomar en consideraci\u00f3n lo establecido en los Decretos 960 de 1970 y 1069 de 2015 sobre la autenticidad de la que gozan las declaraciones emitidas ante un notario, y el proceso de autenticaci\u00f3n de una firma en una notar\u00eda.<\/p>\n<p>85. Igualmente, la Sala advierte que el Juzgado desconoci\u00f3 el tr\u00e1mite dispuesto en el art\u00edculo 85 del C\u00f3digo General del Proceso para probar la existencia y representaci\u00f3n legal de las personas jur\u00eddicas privadas. As\u00ed, el Juzgado no debi\u00f3 exigir de manera autom\u00e1tica al accionante la prueba de existencia y representaci\u00f3n de Cenit, sin que previamente hubiese verificado que tal informaci\u00f3n no reposaba en ninguna de las bases de datos encargadas de su certificaci\u00f3n, pues ello se convirti\u00f3 en una carga para el accionante que la misma Ley elimin\u00f3 con la expedici\u00f3n del C\u00f3digo General del Proceso. As\u00ed, el Juzgado debi\u00f3, primero, consultar su existencia y representaci\u00f3n en las bases de datos de las entidades que tienen a su cargo el deber de certificarla y, despu\u00e9s, y solo en el supuesto de que dicha informaci\u00f3n no estuviese disponible en tales bases de datos, exigir este certificado al accionante.<\/p>\n<p>86. Por otro lado, como lo advirti\u00f3 el Juez de tutela de primera instancia, la Sala estima que, en consideraci\u00f3n a lo dispuesto en los art\u00edculos 132, 133 y 137 del C\u00f3digo General del Proceso, el despacho accionado pudo advertir a la parte demandada de la posible existencia de una nulidad por indebida representaci\u00f3n, para que esta parte la alegara dentro del proceso, se subsanara y as\u00ed continuar con su tr\u00e1mite. El desistimiento t\u00e1cito derivado de omitir las actuaciones del demandante por no reconocer al apoderado, debi\u00f3 ser el \u00faltimo remedio adoptado por el Juzgado, pues se trata de una consecuencia muy gravosa para los derechos del accionante.<\/p>\n<p>87. En tal sentido, debe recordarse que uno de los deberes que tienen los jueces en los procesos es adoptar las medidas autorizadas por la ley procesal para sanear los vicios de procedimiento o precaverlos. Adicionalmente, se reitera que las normas procesales \u201cse encuentran previstas para materializar los derechos de las partes en el marco de los procesos judiciales, que constituyen el fin \u00faltimo del derecho adjetivo\u201d, de modo que estas normas \u201cdeben interpretarse a la luz de los principios de acceso efectivo a la administraci\u00f3n de justicia (art. 229 ibidem) y prevalencia del derecho sustancial (art. 228 ibidem).\u201d<\/p>\n<p>88. Ahora bien, la Sala considera necesario llamar la atenci\u00f3n al accionante, en la medida en que no act\u00fao con total diligencia en el tr\u00e1mite del proceso, pues no respondi\u00f3 al requerimiento realizado por el Juzgado el 19 de julio de 2019 para que aportara los documentos solicitados por el Instituto Agust\u00edn Codazzi, y tampoco puso en conocimiento del Juzgado las razones por las cuales no allegaba el certificado de existencia y representaci\u00f3n legal de la empresa. La solicitud de imposici\u00f3n de aval\u00fao por servidumbre petrolera es un proceso de parte, de modo que es un deber de las partes y sus apoderados prestar toda la colaboraci\u00f3n requerida al juez para la correcta administraci\u00f3n de justicia. M\u00e1xime cuando el proceso fue promovido por el accionante y llevaba casi 10 a\u00f1os sin una decisi\u00f3n de fondo.<\/p>\n<p>89. Segundo defecto procedimental. Terminaci\u00f3n anticipada sin el lleno de los requisitos. Respecto a la terminaci\u00f3n anticipada del proceso de servidumbre petrolera por desistimiento t\u00e1cito, la Sala considera que el Juzgado Primero Civil Municipal de Villavicencio incurri\u00f3 igualmente en un defecto procedimental toda vez que se apart\u00f3 de lo dispuesto en el art\u00edculo 317 del C\u00f3digo General del Proceso, que regula la figura del desistimiento t\u00e1cito. En efecto, en el auto del 23 de octubre de 2020 el despacho accionado adopt\u00f3 la decisi\u00f3n de terminar anticipadamente el proceso sobre la base del presunto incumplimiento de una carga procesal -la no acreditaci\u00f3n del abogado en el proceso- que no corresponde con la que requiri\u00f3 y advirti\u00f3 con claridad en la providencia del 15 de noviembre de 2019 -la aportaci\u00f3n de la documentaci\u00f3n solicitada por el IGAC-. Ello es, de acuerdo con norma mencionada, requisito para la declaratoria del desistimiento t\u00e1cito.<\/p>\n<p>90. En concreto, seg\u00fan lo explic\u00f3 la juez en el auto del 4 de junio de 2020, no era posible realizar \u201clas actuaciones correspondientes ante el IGAC para llevar a consecuci\u00f3n el aval\u00fao de perjuicios\u201d hasta tanto \u201cse acreditara la calidad de la parte actora\u201d, por lo que la terminaci\u00f3n del proceso por desistimiento iba \u201cconcatenada con la puesta en conocimiento para acreditar la calidad de gerente, y por ende, el reconocimiento de personer\u00eda jur\u00eddica para actuar en este proceso\u201d (\u00e9nfasis a\u00f1adido). Se observa entonces que si bien el desistimiento se da por el incumplimiento de lo dispuesto en el auto del 15 de noviembre de 2019 que ordenaba prestar toda la colaboraci\u00f3n necesaria al IGAC para el aval\u00fao, el auto que termina anormalmente el proceso -y que aqu\u00ed se demanda- se funda en la ausencia de reconocimiento de personer\u00eda jur\u00eddica, sin que \u00e9sta \u00faltima hubiera sido advertida en el auto que daba cumplimiento a lo dispuesto en el art\u00edculo 317 del C\u00f3digo General del Proceso, y advert\u00eda la carga procesal a cumplir so pena del desistimiento.<\/p>\n<p>91. Al respecto, la Sala resalta que, dada la consecuencia que trae consigo el desistimiento t\u00e1cito, esto es, la terminaci\u00f3n anticipada del proceso, la ley procesal establece como un requisito esencial para su configuraci\u00f3n que el juez establezca de forma clara, en el auto que advierte de la aplicaci\u00f3n del desistimiento, la carga procesal que debe cumplir la parte so pena de la finalizaci\u00f3n del proceso. De lo contrario, la parte no sabr\u00eda qu\u00e9 acciones realizar para cumplir con lo que el juez requiere, y de esta forma se desnaturalizar\u00eda la finalidad del desistimiento t\u00e1cito.<\/p>\n<p>92. Tercer defecto procedimental. Negativa de tr\u00e1mite de apelaci\u00f3n. Finalmente, frente a la falta de tramitaci\u00f3n del recurso de apelaci\u00f3n interpuesto por el accionante contra el auto que declar\u00f3 el desistimiento t\u00e1cito, la Sala considera que el Juzgado accionado tambi\u00e9n incurri\u00f3 en un defecto procedimental por cuanto desconoci\u00f3 los postulados procesales aplicables al recurso de apelaci\u00f3n contra las decisiones que decreten el desistimiento t\u00e1cito. Al respecto, se advierte que el numeral 5 del art\u00edculo 317 del C\u00f3digo General del Proceso dispone que \u201cla providencia que decrete el desistimiento t\u00e1cito se notificar\u00e1 por estado y ser\u00e1 susceptible del recurso de apelaci\u00f3n en el efecto suspensivo. La providencia que lo niegue ser\u00e1 apelable en el efecto devolutivo.\u201d As\u00ed mismo, el numeral 7 del art\u00edculo 321 establece que el recurso de apelaci\u00f3n procede contra el auto que, por cualquier causa, le ponga fin al proceso. Para la Sala, dado que el punto central del recurso de apelaci\u00f3n interpuesto por el accionante giraba precisamente en torno al reconocimiento del abogado de la empresa Cenit en el proceso, el despacho accionado no pod\u00eda negar el tr\u00e1mite de dicho recurso bajo el fundamento de que el abogado no contaba con personer\u00eda jur\u00eddica para interponerlo. Esta decisi\u00f3n desconoci\u00f3 que precisamente el objetivo de los recursos de apelaci\u00f3n es que el superior examine la decisi\u00f3n en relaci\u00f3n con los reparos concretos formulados por el apelante (Art\u00edculo 320 del C\u00f3digo General del Proceso).<\/p>\n<p>93. As\u00ed mismo, se advierte que si el Juzgado accionado hubiese concedido el recurso de apelaci\u00f3n contra el auto del 23 de octubre de 2020, as\u00ed como lo hizo con el de reposici\u00f3n, ello no habr\u00eda implicado que estuviera reconociendo impl\u00edcitamente la personer\u00eda al abogado dentro del proceso, sino que estaba garantizando el debido proceso a la parte demandante y aplicando los postulados procesales dispuestos sobre esta materia.<\/p>\n<p>94. Al respecto cabe insistir en la importancia de los recursos judiciales, cuya finalidad \u00a0es \u201cpreservar el principio de legalidad y la integridad en la aplicaci\u00f3n del derecho al asegurar la posibilidad de corregir los yerros en que pueda incurrir el juez o fallador en la adopci\u00f3n de una determinada decisi\u00f3n judicial o administrativa\u201d. As\u00ed mismo, la jurisprudencia constitucional ha entendido que la doble instancia, particularmente el recurso de apelaci\u00f3n, \u201ctiene una relaci\u00f3n estrecha con el derecho de defensa, pues a trav\u00e9s del establecimiento de un mecanismo id\u00f3neo y efectivo para asegurar la recta administraci\u00f3n de justicia, (i) garantiza la protecci\u00f3n de los derechos e intereses de quienes acceden al aparato estatal; (ii) permite que la decisi\u00f3n adoptada por una autoridad judicial sea revisada por otro funcionario de la misma naturaleza y la m\u00e1s alta jerarqu\u00eda; (iii) ampl\u00eda la deliberaci\u00f3n sobre la controversia; y (iv) evita la configuraci\u00f3n de yerros judiciales al incrementar la probabilidad de acierto de la justicia como servicio p\u00fablico\u201d.<\/p>\n<p>95. Haber denegado el recurso de apelaci\u00f3n en el caso bajo estudio constituye, adem\u00e1s de un defecto procedimental, una vulneraci\u00f3n al derecho de defensa y la garant\u00edas procesales derivadas de la doble instancia. La juez debi\u00f3 permitir que el superior jer\u00e1rquico revisara su decisi\u00f3n de desistimiento y las razones en que fund\u00f3 dicha terminaci\u00f3n anormal del proceso.<\/p>\n<p>96. En suma, la configuraci\u00f3n de estos defectos procedimentales en el caso objeto de revisi\u00f3n tuvo como consecuencia la vulneraci\u00f3n de los derechos fundamentales al debido proceso, defensa y acceso a la administraci\u00f3n de justicia del accionante, toda vez que, por un lado, no pudo ser o\u00eddo y hacer valer sus argumentos y pruebas en el proceso, as\u00ed como tampoco ejercitar los recursos que ten\u00eda a su alcance, y, por otro lado, dicho proceso fue terminando anticipadamente sin que se decidiera de fondo su pretensi\u00f3n principal y en desconocimiento de los postulados procesales dispuestos para la declaraci\u00f3n del desistimiento t\u00e1cito.<\/p>\n<p>97. En consecuencia, dado que en el caso concreto la Sala encontr\u00f3 que el Juzgado Primero Civil Municipal de Villavicencio incurri\u00f3 en una serie de defectos procedimentales, proceder\u00e1 a conceder el amparo solicitado por el accionante, revocar la decisi\u00f3n del Tribunal Superior del Distrito Judicial de Villavicencio, y confirmar la decisi\u00f3n del Juzgado Quinto Civil del Circuito de Villavicencio.<\/p>\n<p>. S\u00cdNTESIS DE LA DECISI\u00d3N<\/p>\n<p>98. La Sala analiz\u00f3 la configuraci\u00f3n de una serie de defectos procedimentales en los que seg\u00fan el accionante hab\u00eda incurrido el Juzgado Primero Civil Municipal de Villavicencio (Meta) en el auto del 23 de octubre de 2020, que declar\u00f3 el desistimiento t\u00e1cito en el proceso de solicitud de aval\u00fao de servidumbre petrolera. Concluy\u00f3 tales defectos, se habr\u00edan configurado en la medida en que el juez accionado (i) neg\u00f3 desconoci\u00f3 los postulados procesales dispuestos para (i) el reconocimiento de los poderes especiales presentados ante notarios p\u00fablicos en el marco de un proceso judicial (Art\u00edculos 73 y siguientes del C\u00f3digo General del Proceso y Decretos 960 de 1970 y 1069 de 2015); (ii) la comprobaci\u00f3n de la existencia y representaci\u00f3n legal de las personas jur\u00eddicas privadas (Art\u00edculo 85 del C\u00f3digo General del Proceso); (iii) la configuraci\u00f3n del desistimiento t\u00e1cito, en particular, advertencia clara de la carga procesal que debe cumplir la parte so pena de finalizar el proceso anticipadamente (Art\u00edculo 317 del C\u00f3digo General del Proceso); (iv) y el tr\u00e1mite del recurso de apelaci\u00f3n contra las decisiones que decreten el desistimiento t\u00e1cito y terminan el proceso (Numeral 5 del art\u00edculo 317, art\u00edculo 320 y numeral 7 del art\u00edculo 321 del C\u00f3digo General del Proceso).<\/p>\n<p>99. La configuraci\u00f3n de estos defectos procedimentales por parte del despacho accionado tuvo como consecuencia la vulneraci\u00f3n de los derechos fundamentales al debido proceso, defensa y administraci\u00f3n de justicia de la accionante. Por lo tanto, la Sala concedi\u00f3 el amparo de estos derechos al accionante, revoc\u00f3 la decisi\u00f3n de segunda instancia y confirm\u00f3 la decisi\u00f3n de primera instancia.<\/p>\n<p>. DECISI\u00d3N<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Sexta de Revisi\u00f3n de Tutelas de la Corte Constitucional, en nombre del pueblo y por mandato de la Constituci\u00f3n,<\/p>\n<p>RESUELVE<\/p>\n<p>PRIMERO. LEVANTAR la medida provisional impuesta en el Auto 3159 del 15 de diciembre de 2023.<\/p>\n<p>SEGUNDO. REVO<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TEMAS-SUBTEMAS Sentencia T-023\/24 ACCION DE TUTELA CONTRA PROVIDENCIAS JUDICIALES-Procedencia por defecto procedimental (El juez accionado) desconoci\u00f3 los postulados procesales dispuestos para (i) el reconocimiento de los poderes especiales presentados ante notarios p\u00fablicos en el marco de un proceso judicial (Art\u00edculos 73 y siguientes del C\u00f3digo General del Proceso y Decretos 960 de 1970 y 1069 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[146],"tags":[],"class_list":["post-30206","post","type-post","status-publish","format-standard","hentry","category-tutelas-2024"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/30206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=30206"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/30206\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=30206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=30206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=30206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}