{"id":3096,"date":"2024-05-30T17:19:02","date_gmt":"2024-05-30T17:19:02","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/05\/30\/t-055-97\/"},"modified":"2024-05-30T17:19:02","modified_gmt":"2024-05-30T17:19:02","slug":"t-055-97","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-055-97\/","title":{"rendered":"T 055 97"},"content":{"rendered":"<p>T-055-97<\/p>\n<p>&nbsp; &nbsp; Sentencia T-055\/97 &nbsp;<\/p>\n<p>VIA DE HECHO-Aplicaci\u00f3n excepcional &nbsp;<\/p>\n<p>La Corte ha precisado que la figura de la v\u00eda de hecho puede ser aplicada \u00fanicamente de manera excepcional, pues una intromisi\u00f3n permanente del juez constitucional en la esfera de las dem\u00e1s jurisdicciones, adem\u00e1s de propiciar un socavamiento de los \u00e1mbitos propios de cada jurisdicci\u00f3n, constituir\u00eda una violaci\u00f3n del principio de la autonom\u00eda funcional del juez. Es por eso que en el campo de la v\u00eda de hecho esta Corporaci\u00f3n ha se\u00f1alado que \u00e9sta solamente se configura cuando los pronunciamientos judiciales exhiben defectos may\u00fasculos que los alejan de toda noci\u00f3n de la justicia y del imperio de la ley. &nbsp;<\/p>\n<p>JUEZ DE LA CAUSA-Apreciaci\u00f3n y valoraci\u00f3n de pruebas\/JUEZ DE TUTELA-Valoraci\u00f3n excepcional de pruebas en otro proceso &nbsp;<\/p>\n<p>El campo en el que la independencia del juez se mantiene con mayor vigor es el de la valoraci\u00f3n de las pruebas. Ello por cuanto el juez de la causa es el que puede apreciar y valorar de la manera m\u00e1s certera el material probatorio que obra dentro de un proceso. Por eso, la regla general de que la figura de la v\u00eda de hecho solamente puede tener aplicaci\u00f3n en situaciones extremas debe ser manejada de forma a\u00fan m\u00e1s restrictiva cuando se trata de debates acerca de si el material probatorio fue valorado en la debida forma. Solo excepcionalmente puede el juez constitucional entrar a decidir sobre la significaci\u00f3n y la jerarquizaci\u00f3n de las pruebas que obran en un proceso determinado, puesto que \u00e9l no ha participado de ninguna manera en la pr\u00e1ctica de las mismas.&nbsp; &nbsp;<\/p>\n<p>TESTIMONIO-Apreciaci\u00f3n por juez de conocimiento\/JUEZ DE TUTELA-Cautela en an\u00e1lisis de pruebas en otro proceso &nbsp;<\/p>\n<p>La afirmaci\u00f3n de que el juez constitucional debe guiarse por los principios de la cautela y la discreci\u00f3n cuando se trata del an\u00e1lisis del acervo &nbsp;probatorio debatido en una sentencia impugnada por supuesta violaci\u00f3n de los derechos fundamentales, se hace a\u00fan m\u00e1s perentoria cuando las pruebas en discusi\u00f3n son fundamentalmente testimonios. En estas situaciones no cabe sino afirmar que la persona m\u00e1s indicada, por regla general, para apreciar tanto a los testigos como a sus aseveraciones es el juez del proceso, pues \u00e9l es el \u00fanico que puede observar el comportamiento de los declarantes, sus relaciones entre s\u00ed o con las partes del proceso, la forma en que responde al cuestionario judicial, etc.&nbsp; &nbsp;<\/p>\n<p>CONSEJO SUPERIOR DE LA JUDICATURA-Diligencia en decreto de pruebas &nbsp;<\/p>\n<p>Referencia: Expediente T-108866 &nbsp;<\/p>\n<p>Actor: Marcia Florez de Lozano &nbsp;<\/p>\n<p>Magistrado Ponente: &nbsp;<\/p>\n<p>Dr. EDUARDO CIFUENTES MU\u00d1OZ &nbsp;<\/p>\n<p>La Sala Tercera de Revisi\u00f3n de la Corte Constitucional, integrada por los Magistrados Eduardo Cifuentes Mu\u00f1oz, Carlos Gaviria D\u00edaz y Jos\u00e9 Gregorio Hern\u00e1ndez Galindo, ha pronunciado &nbsp;<\/p>\n<p>EN NOMBRE DEL PUEBLO&nbsp; &nbsp;<\/p>\n<p>&nbsp;Y &nbsp;<\/p>\n<p>&nbsp;POR MANDATO DE LA CONSTITUCION &nbsp;<\/p>\n<p>la siguiente &nbsp;<\/p>\n<p>S E N T E N C I A&nbsp; &nbsp;<\/p>\n<p>En el proceso de tutela T-108866 adelantado por MARCIA FLOREZ DE LOZANO contra la SALA JURISDICCIONAL DISCIPLINARIA DEL CONSEJO SUPERIOR DE LA JUDICATURA &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. El 29 de julio de 1996, el apoderado de la Magistrada de la Sala Administrativa del Consejo Seccional de la Judicatura de C\u00f3rdova, Marcia Fl\u00f3rez de Lozano, interpuso acci\u00f3n de tutela, ante la Sala Penal del Tribunal Superior de Cundinamarca, contra la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura, por considerar que esta corporaci\u00f3n vulner\u00f3 sus derechos fundamentales al debido proceso, al trabajo, a la honra y al buen nombre a trav\u00e9s de la providencia expedida el 9 de marzo de 1995. &nbsp;<\/p>\n<p>El representante judicial de la actora relata que el Juez Tercero Penal Municipal de Monter\u00eda, Marcelino Villadiego Polo, present\u00f3 una queja disciplinaria en contra de su poderdante ante la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura, por considerar que \u00e9sta lo hab\u00eda presionado para que nombrara en una vacante de su despacho a la se\u00f1ora Lizmary Jurado Porto. Mediante sentencia fechada el 9 de marzo de 1995, la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura declar\u00f3 la responsabilidad de la demandante al estimar que \u00e9sta hab\u00eda incurrido en la falta disciplinaria tipificada en el literal n) del art\u00edculo 9\u00b0 del Decreto 1888 de 1989, consistente en ejercer influencia indebida sobre el nominador de un determinado cargo. Como consecuencia de lo anterior, la alta corporaci\u00f3n disciplinaria impuso a la actora una multa equivalente a cinco d\u00edas de sueldo b\u00e1sico, decisi\u00f3n de la que se apartaron los magistrados Edgardo Jos\u00e9 Maya Villaz\u00f3n y Amelia Mantilla Villegas.&nbsp; &nbsp;<\/p>\n<p>A juicio del defensor de la demandante, la sentencia proferida por la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura constituye una v\u00eda de hecho por las siguientes razones: (1) se violaron las reglas de la sana cr\u00edtica en la apreciaci\u00f3n de los distintos testimonios, toda vez que s\u00f3lo se tuvieron en cuenta las declaraciones en contra de la actora; (2) los postulados de la sana cr\u00edtica resultaron vulnerados, pues s\u00f3lo se contemplaron aquellos indicios que desfavorec\u00edan a la demandante; y, (3) el extremo subjetivo de la falta disciplinaria no fue tenido en cuenta por la sentencia y, por ende, la peticionaria fue condenada con base en una mera responsabilidad objetiva. El apoderado de la actora se\u00f1ala que &#8220;lo que pretendo demostrar es que la prueba del expediente no es la que se manifiesta en la sentencia; es m\u00e1s: pretendo demostrar que el material recogido en el expediente, no se tuvo en cuenta sino para perjudicar a mi poderdante. La prueba a favor, ni siquiera se la mencion\u00f3: se la dej\u00f3 de lado de manera ol\u00edmpica, porque s\u00ed&#8221;.&nbsp; &nbsp;<\/p>\n<p>El representante judicial de la demandante indica que dentro del proceso disciplinario en menci\u00f3n se recibieron los testimonios de dos de los empleados del Juzgado Tercero Penal Municipal de Monter\u00eda, quienes coincidieron en afirmar que la magistrada Marcia Fl\u00f3rez de Lozano se hab\u00eda presentado en ese despacho judicial para increpar al juez titular por el hecho de no haber nombrado en la vacante del juzgado a Esmeralda Issa Mart\u00ednez Esta habr\u00eda sido expresamente recomendada por Fl\u00f3rez de Lozano al Juez Tercero Municipal de Monter\u00eda, cuando \u00e9ste solicit\u00f3 a la Sala Administrativa del Consejo Seccional de la Judicatura de C\u00f3rdova que le fuera enviada la terna necesaria para proveer el cargo de su despacho que se encontraba libre. Seg\u00fan el apoderado de la actora, los declarantes se\u00f1alaron que, gracias a que se encontraban cerca al despacho del juez y la puerta de \u00e9ste no se encontraba cerrada, pudieron escuchar c\u00f3mo la magistrada Fl\u00f3rez de Lozano alzaba la voz para amenazar al juez dici\u00e9ndole que &#8220;no creyera que porque estaba nombrado en propiedad nada pod\u00eda pasarle&#8221; y que &#8220;recordara que ella hab\u00eda sido nombrada por un lapso de cuatro a\u00f1os&#8221;, luego de lo cual se retir\u00f3 en forma &#8220;brusca y disgustada&#8221;. &nbsp; &nbsp;<\/p>\n<p>En opini\u00f3n del apoderado de la peticionaria, la sentencia proferida por la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura se bas\u00f3 en los testimonios antes rese\u00f1ados para probar la presencia de la magistrada Marcia Fl\u00f3rez de Lozano en el despacho del Juez Tercero Penal Municipal de Monter\u00eda, presencia que, a su turno, fue considerada como un indicio claro del intento de la actora de influir en el Juez Tercero Penal Municipal de Monter\u00eda para que \u00e9ste nombrara en el cargo vacante a su recomendada.&nbsp; &nbsp;<\/p>\n<p>El representante judicial de la actora afirma que la providencia del 9 de marzo ignor\u00f3 dos testimonios que desvirtuaban lo afirmado por los dos empleados del Juzgado Tercero Penal Municipal de Monter\u00eda. En efecto, no fueron tenidas en cuenta las declaraciones de dos compa\u00f1eros del posgrado en derecho penal que cursaba el Juez Tercero Penal Municipal de Monter\u00eda (uno de ellos Juez Segundo Penal Municipal de Monter\u00eda), quienes afirmaron que, un d\u00eda en que deb\u00edan reunirse con este funcionario judicial en su despacho para realizar un trabajo de la anotada especializaci\u00f3n, al pretender abrir la puerta de la oficina de su compa\u00f1ero, fueron informados por uno de los empleados del juzgado que el juez se encontraba reunido con la magistrada Marcia Fl\u00f3rez de Lozano. De igual forma, el apoderado indic\u00f3 que, uno de estos testigos, puso de presente que hab\u00eda &#8220;visto bien de \u00e1nimo&#8221; a Fl\u00f3rez de Lozano cuando \u00e9sta abandon\u00f3 el despacho del Juez Tercero Penal Municipal de Monter\u00eda.&nbsp; &nbsp;<\/p>\n<p>A juicio del defensor de la demandante, las declaraciones anteriores desvirt\u00faan los testimonios de los dos empleados del Juzgado Tercero Penal Municipal de Monter\u00eda, en el punto relativo a que hab\u00edan podido escuchar la conversaci\u00f3n que sosten\u00edan el juez y la magistrada Fl\u00f3rez de Lozano, gracias a que la puerta del despacho se encontraba abierta, como quiera que los compa\u00f1eros de posgrado del juez tercero afirmaron que cuando se dispusieron a abrir la puerta de la oficina de este funcionario judicial fueron detenidos por los empleados del juzgado. Seg\u00fan el apoderado, &#8220;si se dispusieron a abrir la puerta, era porque estaba cerrada; y si la puerta estaba cerrada, los testigos de cargo no pudieron escuchar la conversaci\u00f3n que se suced\u00eda adentro entre la magistrada y el juez&#8221;.&nbsp; &nbsp;<\/p>\n<p>De otra parte, el representante judicial de actora alega que la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura, al dictar la sentencia atacada, debi\u00f3 desconfiar del testimonio de los dos empleados del Juzgado Tercero Penal Municipal de Monter\u00eda, en raz\u00f3n de la relaci\u00f3n de dependencia entre \u00e9stos y el titular de ese despacho quien, como ya se anot\u00f3, fue quien interpuso la queja disciplinaria en contra de la demandante. El apoderado indica que lo anterior se encuadra dentro de la doctrina en materia de derecho probatorio seg\u00fan la cual determinados testigos son sospechosos habida cuenta de su especial inter\u00e9s en mentir y, por ello, su declaraci\u00f3n debe ser sometida a una apreciaci\u00f3n mucho m\u00e1s exigente por parte del juzgador.&nbsp; &nbsp;<\/p>\n<p>En este orden de ideas afirma que &#8220;en la sentencia no se tiene en cuenta la inidoneidad moral de los testigos, ni la contradicci\u00f3n esencial con otras pruebas del proceso que hacen manifestaciones contrarias a sus aseveraciones y que cortan de tajo la posibilidad de que hubiesen percibido el di\u00e1logo entre el juez y la magistrada&#8221;. Igualmente, manifiesta que &#8220;a la sentencia no le preocup\u00f3 la sospechosa coincidencia en la forma, en la comunidad de expresiones ling\u00fc\u00edsticas que existe entre los declarantes, la sincronizaci\u00f3n de las palabras, aspecto bien estudiado ya en la doctrina como signo de sospecha. (&#8230;). Para ponerse en guardia en relaci\u00f3n con los testigos de cargo, los empleados del Dr. Marcelino Villadiego Polo, hubiera bastado la sospechosa coincidencia no ya en el contenido, o en el sentido de la conversaci\u00f3n que supuestamente escucharon, sino en la particular coincidencia de las palabras mismas, la cual hace ver las declaraciones como unas verdaderas fotocopias entre s\u00ed&#8221;.&nbsp; &nbsp;<\/p>\n<p>Por otro lado, el apoderado de la actora expone que los testimonios rendidos por los empleados del Juzgado Tercero Penal Municipal de Monter\u00eda tambi\u00e9n resultan desvirtuados en punto a las manifestaciones de que, luego de la conversaci\u00f3n sostenida con el Juez Tercero Penal Municipal de Monter\u00eda, la magistrada Marcia Fl\u00f3rez de Lozano se hab\u00eda retirado del despacho judicial mostr\u00e1ndose bastante alterada, &#8220;se entiende que por no haberle hecho caso (el juez) en el nombramiento de la persona en la que supuestamente estaba interesada&#8221;. Efectivamente, lo anterior resultar\u00eda controvertido por las declaraciones de los compa\u00f1eros de posgrado del Juez Tercero Penal Municipal de Monter\u00eda, uno de los cuales afirm\u00f3 que hab\u00eda visto &#8220;bien de \u00e1nimo&#8221; a Fl\u00f3rez de Lozano, mientras que el otro asever\u00f3 que no le hab\u00eda puesto atenci\u00f3n &#8220;ni a la actitud del doctor Villadiego ni mucho menos a la doctora Fl\u00f3rez de Lozano&#8221;. Seg\u00fan el representante judicial, &#8220;la anterior expresi\u00f3n desmiente a los testigos de cargo, pues si en verdad hubiese estado la doctora Marcia Fl\u00f3rez alterada, como quiera que la emoci\u00f3n de la ira es notable por sus resonancias fisiol\u00f3gicas, es f\u00e1cilmente perceptible&#8221;.&nbsp; &nbsp;<\/p>\n<p>De otra parte, el apoderado de la demandante se\u00f1al\u00f3 que otro de los testimonios cuyo contenido se utiliz\u00f3 para declarar la responsabilidad disciplinaria de su poderdante, fue el del magistrado de la Sala Civil del Tribunal Superior de Monter\u00eda, Joaqu\u00edn Esquivia L\u00f3pez, quien afirm\u00f3 que, luego de haber visitado al Juez Tercero Penal Municipal de Monter\u00eda, la magistrada Marcia Fl\u00f3rez de Lozano hab\u00eda subido a su oficina para manifestarle -bastante alterada- que &#8220;Marcelino la hab\u00eda enga\u00f1ado por cuanto no le hab\u00eda nombrado la persona que ella le hab\u00eda recomendado&#8221;. En opini\u00f3n del representante judicial, esta declaraci\u00f3n tampoco fue apreciada por la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura seg\u00fan los postulados de la sana cr\u00edtica, toda vez que, a su turno, el magistrado Esquivia L\u00f3pez ejerci\u00f3 influencias para que, en la vacante del Juzgado Tercero Penal Municipal de Monter\u00eda, fuera nombrada la persona que, efectivamente, accedi\u00f3 al cargo. Lo anterior se deduce, seg\u00fan el apoderado de la actora, de los testimonios de dos magistrados del Consejo Seccional de la Judicatura de C\u00f3rdova, Ram\u00f3n de Jes\u00fas Jaller y Alvaro D\u00edaz Brieva, quienes manifestaron que Esquivia L\u00f3pez se hab\u00eda comunicado con ellos para solicitarles que incluyeran a Esmeralda Issa Mart\u00ednez dentro de la terna que deb\u00eda enviarse al Juez Tercero Penal Municipal de Monter\u00eda, para que \u00e9ste proveyera el cargo vacante en ese despacho. &nbsp;<\/p>\n<p>Sin embargo, en su testimonio, el magistrado Esquivia L\u00f3pez afirm\u00f3 que no hab\u00eda influido en el nombramiento de Esmeralda Issa, toda vez que no conoc\u00eda &#8220;cuales son las personas que aparecen en el registro del Consejo Seccional&#8221;. De igual modo, reconoci\u00f3 que, una vez que el Juez Tercero Penal Municipal de Monter\u00eda recibi\u00f3 la terna de la cual habr\u00eda de nombrar a la persona para proveer el cargo vacante en su despacho, \u00e9ste se acerc\u00f3 a su oficina para preguntarle si &#8220;estaba obligado a nombrar una persona determinada de la lista que le hab\u00eda mandado el Consejo Seccional&#8221;. Frente a lo anterior, el apoderado de la demandante se pregunta: &#8220;si el Dr. Esquivia ya hab\u00eda insinuado a los doctores Jaller Dumar y D\u00edaz Brieva que incluyeran en la lista de elegibles a la se\u00f1orita Esmeralda Issa Mart\u00ednez, lo que en efecto hab\u00eda ocurrido, si ten\u00eda un marcado inter\u00e9s en tal nombramiento, ser\u00e1 veros\u00edmil que cuando habl\u00f3 con quien iba a ser el nominador ninguna insinuaci\u00f3n hizo para que se concretara? Para no hacer de nuevo la sugerencia o pedir directamente que se nombrara a su pupila, el Dr. Esquivia tendr\u00eda que tener caracter\u00edsticas angelicales, lejos de \u00e9l, a juzgar por lo que reza el expediente!!! No: el Dr. Esquivia ten\u00eda un marcado inter\u00e9s en el nombramiento de la se\u00f1orita Issa Mart\u00ednez, le dijo al juez que la nombrara y por eso el juez le dijo a la magistrada Fl\u00f3rez que hab\u00eda nombrado a la mencionada para cumplirle los deseos en ese sentido al Dr. Esquivia&#8221;.&nbsp; &nbsp;<\/p>\n<p>El representante judicial de la magistrada Marcia Fl\u00f3rez de Lozano precisa que la poca credibilidad que, seg\u00fan los principios de la sana cr\u00edtica, deb\u00eda otorgarse al testimonio de Esquivia L\u00f3pez fue se\u00f1alada por los magistrados Amelia Mantilla Villegas y Edgardo Jos\u00e9 Maya Villaz\u00f3n, en sus respectivos salvamentos de voto a la providencia de marzo 9 de 1995, proferida por la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura. &nbsp; &nbsp;<\/p>\n<p>De igual forma, el apoderado de la peticionaria manifiesta que la sentencia atacada incurri\u00f3 en graves fallas al desconocer reglas elementales de la sana cr\u00edtica en punto a la valoraci\u00f3n de la prueba indiciaria. A su juicio, el juez disciplinario tuvo como indicio principal del inter\u00e9s de la magistrada Fl\u00f3rez de Lozano en el nombramiento de Lizmary Jurado Porto, la presencia de aquella en el despacho del Juez Tercero Penal Municipal de Monter\u00eda. Afirma que lo anterior no se ajusta a los &#8220;principios elementales&#8221; del an\u00e1lisis del indicio y que, por lo tanto, no era posible concederle la fuerza probatoria que efectivamente se le otorg\u00f3.&nbsp; &nbsp;<\/p>\n<p>Para sustentar su afirmaci\u00f3n, el representante judicial expresa que, luego de haber remitido al Juez Tercero Penal Municipal la lista de elegibles para que proveyera el cargo vacante, la magistrada Fl\u00f3rez de Lozano recibi\u00f3 una llamada y un an\u00f3nimo a trav\u00e9s de los cuales se pusieron en su conocimiento ciertas cualidades personales de la se\u00f1orita Esmeralda Issa Mart\u00ednez, &#8220;que a su modo de ver no la hac\u00edan apta para el cargo, comprometido como est\u00e1 el Consejo Superior de la Judicatura en la purificaci\u00f3n de la Administraci\u00f3n de Justicia&#8221;. Esta circunstancia desvirtuar\u00eda lo aseverado en la sentencia de marzo 9 de 1995 acerca de que &nbsp;&#8220;no cabe tampoco considerar que su actitud [la de Fl\u00f3rez de Lozano] obedec\u00eda al hecho de que la favorecida con el nombramiento hab\u00eda sido censurada con reserva moral. Y ello porque si as\u00ed hubiese sido, la elegida no tendr\u00eda por qu\u00e9 haber figurado en la lista de elegibles&#8221;. Seg\u00fan el apoderado, la anterior afirmaci\u00f3n desconoce en forma flagrante el hecho de que &#8220;en el proceso est\u00e1 probado hasta la saciedad que lo de la eventual tacha o reserva moral, s\u00f3lo se supo despu\u00e9s de haber enviado la lista al juzgado Tercero Penal Municipal: la lista fue enviada el 22 de febrero de 1994 y las llamadas y an\u00f3nimos se recibieron entre el 22 y el 25&#8221;.&nbsp; &nbsp;<\/p>\n<p>Asevera que la conclusi\u00f3n anterior se encuentra confirmada por el testimonio del magistrado Alvaro D\u00edaz Brieva, quien afirm\u00f3 haber recibido una llamada an\u00f3nima en la que su interlocutor se refiri\u00f3 a la se\u00f1orita Esmeralda Issa Mart\u00ednez en &#8220;t\u00e9rminos desobligantes&#8221;. Igualmente, D\u00edaz Brieva puso de presente que, encontr\u00e1ndose en la ciudad de Cartagena para asistir a un curso de especializaci\u00f3n, la magistrada Marcia Fl\u00f3rez de Lozano se comunic\u00f3 con \u00e9l telef\u00f3nicamente para informarle que tambi\u00e9n hab\u00eda recibido comunicados an\u00f3nimos referentes a la conducta de Issa Mart\u00ednez, en raz\u00f3n de lo cual acordaron sugerirle al Juez Tercero Penal Municipal de Monter\u00eda que, al proveer el cargo vacante, optara por alguna de las otras dos integrantes que figuraban en la lista de elegibles. Esto \u00faltimo, a juicio del representante judicial, confirma la versi\u00f3n de la demandante en relaci\u00f3n con su presencia en el Juzgado Tercero Penal Municipal, quien afirma que \u00e9sta se debi\u00f3 exclusivamente a la necesidad de advertir al titular de ese despacho judicial acerca de las dudas que se presentaban en torno a la idoneidad moral de Esmeralda Issa Mart\u00ednez.&nbsp; &nbsp;<\/p>\n<p>El apoderado de la actora manifiesta que, pese a lo anterior, el testimonio de D\u00edaz Brieva no fue tomado en cuenta por la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura en su sentencia de marzo 9 de 1995, lo cual, en su concepto, viola el principio de derecho probatorio seg\u00fan el cual un indicio puede ser considerado como necesario solamente cuando se puede llegar a la conclusi\u00f3n de que se deriva de una \u00fanica causa. Si, por el contrario, el hecho indiciario pudo haber sido producido por diversas razones, entonces se trata de un indicio probable que determina la necesidad de establecer cu\u00e1l es la causa verdadera entre las distintas posibles. Esto \u00faltimo, aplicado al caso de autos, determina que la presencia de Fl\u00f3rez de Lozano en el despacho del Juez Tercero Penal Municipal de Monter\u00eda constitu\u00eda tan s\u00f3lo un indicio probable, toda vez que tal presencia pod\u00eda deberse bien a su intenci\u00f3n de presionar al juez para que nombrara a su pupila, o bien para advertirle -como afirman la actora y el magistrado D\u00edaz Brieva- acerca de la reserva moral que pesaba sobre Issa Mart\u00ednez. Sobre este punto, el representante judicial indica que &#8220;la sentencia est\u00e1 lejos de examinar los puntos anteriores: no deja campo a otra alternativa para la presencia de la magistrada en el despacho del Juez Tercero Penal, que no sea la de presionar; olvida la otra alternativa que surge de la declaraci\u00f3n de la doctora Fl\u00f3rez, la cual est\u00e1 respaldada por el Dr. D\u00edaz Brieva&#8221;.&nbsp; &nbsp;<\/p>\n<p>Por otro lado, el representante judicial de la demandante puso de presente que, en su testimonio, el Juez Tercero Penal Municipal de Monter\u00eda, manifest\u00f3 haber sido citado al despacho de la magistrada Marcia Fl\u00f3rez de Lozano, oportunidad en la cual \u00e9sta aprovech\u00f3 para tratar de influir en \u00e9l. Sin embargo, indic\u00f3 que, luego de la inspecci\u00f3n judicial llevada a cabo el 1\u00b0 de noviembre de 1994 a los libros de registro de visitantes del Consejo Seccional de la Judicatura de C\u00f3rdova, pudo establecerse que, en los anotados libros, no aparec\u00eda ning\u00fan registro que indicara que, en alguna oportunidad, el Juez Tercero Penal Municipal de Monter\u00eda hubiese visitado a la magistrada Fl\u00f3rez de Lozano. Sobre este particular el apoderado afirm\u00f3 que &#8220;si el juez dice que estuvo en el despacho de la magistrada en donde fue presionado o insinuado, y si la prueba lo desmiente, esto cuenta a favor de la acusada y no en contra. Sin embargo a esa prueba a favor ninguna importancia se le da en la sentencia&#8221;.&nbsp; &nbsp;<\/p>\n<p>A juicio del representante judicial de la demandante, \u00e9sta fue condenada &#8220;sin tener en cuenta el elemento subjetivo del delito, y s\u00f3lo con base en el hecho objetivo de haber estado en el despacho del Juez Tercero Penal Municipal , sin valorar el hecho en su pleno significado. (&#8230;). La presencia en el Juzgado Tercero Penal Municipal, no fue a t\u00edtulo personal sino en nombre de la Instituci\u00f3n, Consejo Seccional como lo indica tambi\u00e9n el Dr. D\u00edaz Brieva. En estas circunstancias, no se tuvo en cuenta que ning\u00fan dolo, ninguna culpabilidad puede predicarse de su comportamiento como para que se pueda decir que existe falta disciplinaria&#8221;. &nbsp; &nbsp;<\/p>\n<p>Con base en todo lo anterior, el apoderado concluye que la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura hab\u00eda incurrido en una manifiesta v\u00eda de hecho. Afirma que &#8220;la sentencia lo es en apariencia: pero si consultamos su fundamento, observamos en ella concretada la m\u00e1s aberrante de las injusticias: se llev\u00f3 de calle el debido proceso. (&#8230;). Es cierto que en nuestro sistema rige el criterio de la libre apreciaci\u00f3n, pero se trata de una apreciaci\u00f3n razonada, no arbitraria&#8221;. En su opini\u00f3n, las distintas fallas en la apreciaci\u00f3n del acervo probatorio conculcan lo dispuesto por el art\u00edculo 254 del C\u00f3digo de Procedimiento Penal, seg\u00fan el cual &#8220;las pruebas deber\u00e1n ser apreciadas en conjunto, de acuerdo a las reglas de la sana cr\u00edtica&#8221;.&nbsp; &nbsp;<\/p>\n<p>Se\u00f1ala que, si bien la acci\u00f3n de tutela no constituye ni una instancia para la defensa de derechos ordinarios ni un medio alternativo, adicional o complementario para la protecci\u00f3n de los mismos, en el caso de la magistrada Marcia Fl\u00f3rez de Lozano, &#8220;a pesar de que ella compareci\u00f3 al proceso, todo comportamiento suyo defensivo result\u00f3 inocuo por la manera arbitraria como se manej\u00f3 la prueba: s\u00f3lo se tuvo en cuenta la que la oprim\u00eda y nunca, en ning\u00fan momento se tuvo en cuenta para nada la que la liberaba. Se ha dicho que la acci\u00f3n de tutela no procede cuando el proceso se ha concluido con una providencia que pone fin al proceso; pero, pregunto, qu\u00e9 hacer entonces cuando contra esa providencia no procede recurso alguno a pesar de ser aberrantemente injusta?&#8221;. &nbsp;&nbsp; &nbsp;<\/p>\n<p>Por \u00faltimo, el apoderado de la actora se\u00f1ala que la providencia de marzo 9 de 1995, proferida por la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura, vulnera los derechos fundamentales a la honra y al buen nombre de su poderdante, toda vez que &#8220;la sentencia resumir\u00eda que la doctora Fl\u00f3rez por lo menos es una persona indecorosa que anda presionando e intrigando a sus inferiores para que cumplan sus deseos: con ese Inri, no creo que la existencia de la doctora Fl\u00f3rez sea la mejor&#8221;. De igual forma, y en la medida en que el art\u00edculo 84 de la Ley Estatutaria de la Administraci\u00f3n de Justicia (Ley 270 de 1996) dispone que para ser magistrado de las salas administrativas de los consejos seccionales de la judicatura no se podr\u00e1n tener antecedentes disciplinarios, la sentencia atacada viola el derecho al trabajo de la demandante.&nbsp; &nbsp;<\/p>\n<p>En raz\u00f3n de todo lo anterior, el representante judicial de la magistrada Marcia Fl\u00f3rez de Lozano solicita: (1) que se revoque la providencia de marzo 9 de 1995, proferida por la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura; y, (2) que se adopten las medidas necesarias para dejar sin efectos el acto de ejecuci\u00f3n por medio del cual se haya dado cumplimiento a la sentencia atacada.&nbsp; &nbsp;<\/p>\n<p>En consecuencia, remiti\u00f3 la actuaci\u00f3n al Tribunal Superior del Distrito Judicial de Santa Fe de Bogot\u00e1, &#8220;proponi\u00e9ndole desde ya, colisi\u00f3n negativa de competencia en caso de no compartir los argumentos expuestos&#8221;. &nbsp;<\/p>\n<p>3. El 28 de agosto de 1996, la Sala Penal del Tribunal Superior del Distrito Judicial de Santa Fe de Bogot\u00e1 neg\u00f3 por improcedente la tutela solicitada por el apoderado de la magistrada Marcia Fl\u00f3rez de Lozano.&nbsp; &nbsp;<\/p>\n<p>En primer lugar, record\u00f3 que la acci\u00f3n de tutela contra decisiones judiciales s\u00f3lo es procedente en aquellos casos en que \u00e9stas constituyan una v\u00eda de hecho. &nbsp;<\/p>\n<p>A juicio del Tribunal, el proceso disciplinario que se sigui\u00f3 contra la actora &#8220;se adelant\u00f3 con el lleno de las garant\u00edas legales y constitucionales&#8221;. Asegura que &nbsp;ella fue vinculada en debida forma a la actuaci\u00f3n y que se le permiti\u00f3 controvertir las pruebas allegadas, raz\u00f3n por la cual considera que no es de recibo afirmar, como lo hace el apoderado de la actora, que se configura una v\u00eda de hecho en raz\u00f3n de la valoraci\u00f3n efectuada al acervo probatorio. &nbsp;<\/p>\n<p>A\u00f1ade que el estudio probatorio realizado en la providencia de marzo 9 de 1995 se llev\u00f3 a cabo &#8220;en forma arm\u00f3nica y concatenada, con la suficiente controversia; tanto que conllev\u00f3 a que dos de los integrantes de la Sala manifestaran su desacuerdo con la decisi\u00f3n mayoritaria; luego es indudable que el caudal probatorio se someti\u00f3 a la debida valoraci\u00f3n y condujo a la decisi\u00f3n final, que aunque no compartida por la totalidad de los Magistrados, s\u00ed constituye determinaci\u00f3n con efectos de cosa juzgada&#8221;. &nbsp;<\/p>\n<p>Afirma que la decisi\u00f3n de la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura tiene sustento legal y probatorio, raz\u00f3n por la cual no cabe la tutela y concluye que no puede pensarse en la existencia de una v\u00eda de hecho cuando &#8220;la inconformidad del peticionario y su poderdante radica en la conclusi\u00f3n final a la que se lleg\u00f3 con base en el caudal probatorio&#8221;.&nbsp; &nbsp;<\/p>\n<p>La anterior decisi\u00f3n fue enviada a la Corte Constitucional para su eventual revisi\u00f3n y, al ser seleccionada, correspondi\u00f3 a esta Sala su conocimiento. &nbsp;<\/p>\n<p>FUNDAMENTOS JURIDICOS&nbsp; &nbsp;<\/p>\n<p>1. &#8211; El Consejo Superior de la Judicatura -Sala Disciplinaria &#8211; le impuso la sanci\u00f3n de multa de cinco d\u00edas de salario a la doctora Marcia Fl\u00f3rez de Lozano, magistrada del Consejo Seccional de la Judicatura de C\u00f3rdoba -Sala Administrativa-, bajo la consideraci\u00f3n de que hab\u00eda incurrido en la falta tipificada en el ordinal n) del art\u00edculo 9 del decreto 1888 de 1989, &#8220;por incumplir las normas sobre nombramientos, al ejercer influencia indebida sobre el doctor MARCELINO MANUEL VILLADIEGO POLO, Juez Tercer Penal Municipal de Monter\u00eda, en el caso de la designaci\u00f3n de la se\u00f1orita ESMERALDA LUCIA ISSA MARTINEZ, sustanciadora grado Octavo del citado Despacho Judicial&#8221; (may\u00fasculas originales).&nbsp; &nbsp;<\/p>\n<p>2. El apoderado de la actora manifiesta que en la sentencia del Consejo Superior de la Judicatura se viol\u00f3 el derecho al debido proceso de su poderdante, y por contera sus derechos al trabajo, a la honra y al buen nombre, en tanto que en el an\u00e1lisis de las &nbsp;pruebas obrantes en el proceso no se siguieron las reglas de la &#8220;sana cr\u00edtica&#8221;. Asevera que en la providencia solamente se tuvieron en cuenta las pruebas en contra de su asistida, mientras que los medios probatorios que la favorec\u00edan fueron descartados. Por tal raz\u00f3n, considera que la providencia constituye en realidad una v\u00eda de hecho.&nbsp; &nbsp;<\/p>\n<p>3. La Sala Penal del Tribunal Superior de Bogot\u00e1 deneg\u00f3 la tutela impetrada por el apoderado de la actora. Manifiesta que en el proceso tuvieron vigencia todas las garant\u00edas constitucionales y legales y que la decisi\u00f3n de la Sala Jurisdiccional Disciplinaria del Consejo Superior de la Judicatura tiene su debido sustento legal y probatorio. Considera que las pruebas fueron suficientemente controvertidas y valoradas.&nbsp; &nbsp;<\/p>\n<p>4. En la sentencia SU-637 de 1996, esta Corporaci\u00f3n revoc\u00f3 una sentencia proferida por el Consejo Superior de la Judicatura, en raz\u00f3n de que el fallo sancionatorio proferido por \u00e9sta se fundamentaba en el decreto 1888 de 1989, hecho \u00e9ste que configuraba una v\u00eda de hecho. En aquella ocasi\u00f3n, la Corte Constitucional expres\u00f3 que, en el &nbsp;ejercicio de su labor disciplinaria sobre los funcionarios judiciales, el Consejo Superior y los Consejos Seccionales de la Judicatura deb\u00edan aplicar el C\u00f3digo Disciplinario Unico &#8211; Ley 200 de 1995 -, el cual derog\u00f3 el Decreto 1888 de 1989. Asimismo, se\u00f1al\u00f3 que los art\u00edculos 150 a 154 de la Ley Estatutaria de la Administraci\u00f3n de Justicia tambi\u00e9n deb\u00edan ser considerados cuando se tratase de juicios disciplinarios contra los funcionarios judiciales.&nbsp; &nbsp;<\/p>\n<p>La &nbsp;sanci\u00f3n impuesta a la magistrada Fl\u00f3rez de Lozano se bas\u00f3 en el decreto 1888 de 1989. Sin embargo, en este caso concreto no se advierte la existencia de una v\u00eda de hecho, por esta causal, en la decisi\u00f3n del Consejo Superior de la Judicatura, puesto que la sentencia impugnada fue dictada el d\u00eda 9 de marzo de 1995, mientras que el C\u00f3digo Disciplinario Unico entr\u00f3 a regir 45 d\u00edas despu\u00e9s de su sanci\u00f3n presidencial, la cual ocurri\u00f3 el d\u00eda 28 de julio de 1995. &nbsp;<\/p>\n<p>5. Ahora bien, el apoderado de la actora fundamenta su petici\u00f3n de que la sentencia del Consejo Superior de la Judicatura sea declarada como una v\u00eda de hecho en la afirmaci\u00f3n de que las pruebas que reposan en el expediente no fueron valoradas debidamente. Para poder entrar a decidir sobre este aspecto es importante recordar algunos pronunciamientos de esta Corporaci\u00f3n sobre el tema.&nbsp; &nbsp;<\/p>\n<p>En primer t\u00e9rmino, debe dejarse en claro que la Corte ha precisado que la figura de la v\u00eda de hecho puede ser aplicada \u00fanicamente de manera excepcional, pues una intromisi\u00f3n permanente del juez constitucional en la esfera de las dem\u00e1s jurisdicciones, adem\u00e1s de propiciar un socavamiento de los \u00e1mbitos propios de cada jurisdicci\u00f3n, constituir\u00eda una violaci\u00f3n del principio de la autonom\u00eda funcional del juez. Al respecto se manifest\u00f3 en la sentencia T-231 de 1994:&nbsp; &nbsp;<\/p>\n<p>&#8220;3. El principio de independencia judicial (CP arts. 228 y 230), no autoriza a que un juez ajeno al proceso, cuya intervenci\u00f3n no se contempla en la norma que establece el procedimiento y los recursos, pueda revisar los autos y providencias que profiera el juez del conocimiento. La valoraci\u00f3n de las pruebas y la aplicaci\u00f3n del derecho, son extremos que se libran al Juez competente y a las instancias judiciales superiores llamadas a decidir los recursos que, de conformidad con la ley, puedan interponerse contra sus autos y dem\u00e1s providencias. Tanto el juez de instancia como sus superiores, cada uno dentro de la \u00f3rbita de sus competencias, son aut\u00f3nomos e independientes, y adoptan sus decisiones sometidos \u00fanicamente &#8220;al imperio de la ley&#8221; (CP art. 230). Las injerencias contra las cuales reacciona el principio de independencia judicial, no se reducen a las que pueden provenir de otras ramas del poder p\u00fablico o que emanen de sujetos particulares; tambi\u00e9n pertenecen a ellas las surgidas dentro de la misma jurisdicci\u00f3n o de otras, y que no respeten la autonom\u00eda que ha de predicarse de todo juez de la Rep\u00fablica, pues en su adhesi\u00f3n directa y no mediatizada al derecho se cifra la imparcial y correcta administraci\u00f3n de justicia&#8221;. &nbsp;<\/p>\n<p>&#8220;Obs\u00e9rvese que los defectos calificados como v\u00eda de hecho &nbsp;son aquellos que tienen una dimensi\u00f3n superlativa y que, en esa misma medida, agravian el ordenamiento jur\u00eddico. Los errores ordinarios, a\u00fan graves, de los jueces in iudicando o in procedendo, no franquean las puertas de este tipo de control que, por lo visto, se reserva para los que en grado absoluto y protuberante se apartan de los dictados del derecho y de sus principios y que, por lo tanto, en la forma o en su contenido traslucen un comportamiento arbitrario y puramente voluntarista por parte del juez que los profiere&#8221;. &nbsp;<\/p>\n<p>6. El campo en el que la independencia del juez se mantiene con mayor vigor es el de la valoraci\u00f3n de las pruebas. Ello por cuanto el juez de la causa es el que puede apreciar y valorar de la manera m\u00e1s certera el material probatorio que obra dentro de un proceso. El es el que puede sopesar de la mejor manera los testimonios, el que ha concurrido a las inspecciones judiciales y el que conoce a las partes y a su entorno. Por eso, la regla general de que la figura de la v\u00eda de hecho solamente puede tener aplicaci\u00f3n en situaciones extremas debe ser manejada de forma a\u00fan m\u00e1s restrictiva cuando se trata de debates acerca de si el material probatorio fue valorado en la debida forma. Solo excepcionalmente puede el juez constitucional entrar a decidir sobre la significaci\u00f3n y la jerarquizaci\u00f3n de las pruebas que obran en un proceso determinado, puesto que \u00e9l no ha participado de ninguna manera en la pr\u00e1ctica de las mismas.&nbsp; &nbsp;<\/p>\n<p>Precisamente sobre este punto se pronunci\u00f3 la Corte en la sentencia T-442 de 1994 (M.P. Antonio Barrera Carbonell), en la cual se expres\u00f3: &nbsp;<\/p>\n<p>&#8220;No obstante lo anterior advierte la Sala, que s\u00f3lo es factible fundar una acci\u00f3n de tutela, cuando se observa que de una manera manifiesta aparece irrazonable la valoraci\u00f3n probatoria hecha por el juez en la correspondiente providencia. El error en el juicio valorativo de la prueba debe ser de tal entidad que sea ostensible, flagrante y manifiesto, y el mismo debe tener una incidencia directa en la decisi\u00f3n, pues el juez de tutela no puede convertirse en una instancia revisora de la actividad de evaluaci\u00f3n probatoria del juez que ordinariamente conoce de un asunto, seg\u00fan las reglas generales de competencia, porque ello ser\u00eda contrario al principio de que la tutela es un medio alternativo de defensa judicial, aparte de que se invadir\u00eda la \u00f3rbita de la competencia y la autonom\u00eda de que son titulares las otras jurisdicciones&#8221;. &nbsp;<\/p>\n<p>La afirmaci\u00f3n de que el juez constitucional debe guiarse por los principios de la cautela y la discreci\u00f3n cuando se trata del an\u00e1lisis del acervo &nbsp;probatorio debatido en una sentencia impugnada por supuesta violaci\u00f3n de los derechos fundamentales, se hace a\u00fan m\u00e1s perentoria cuando las pruebas en discusi\u00f3n son fundamentalmente testimonios. En estas situaciones no cabe sino afirmar que la persona m\u00e1s indicada, por regla general, para apreciar tanto a los testigos como a sus aseveraciones es el juez del proceso, pues \u00e9l es el \u00fanico que puede observar el comportamiento de los declarantes, sus relaciones entre s\u00ed o con las partes del proceso, la forma en que responde al cuestionario judicial, etc.&nbsp; &nbsp;<\/p>\n<p>7. La primera conclusi\u00f3n a la que se puede llegar despu\u00e9s de examinar la sentencia del Consejo Superior de la Judicatura es que \u00e9ste procedi\u00f3 de manera diligente en punto al decreto de pruebas para un mejor establecimiento de los hechos. &nbsp;En efecto, el Consejo Superior de la Judicatura no se conform\u00f3 con la pruebas aportadas por el Juez Tercero Penal Municipal de Monter\u00eda, sino que orden\u00f3 la pr\u00e1ctica de diversas inspecciones judiciales y diferentes testimonios, todo de acuerdo con la solicitud que formul\u00f3 la magistrada Fl\u00f3rez de Lozano. Esta conclusi\u00f3n puede sustentarse tambi\u00e9n en el escrito del apoderado de la actora, puesto que la cr\u00edtica que en \u00e9l se formula se dirige es contra una presunta valoraci\u00f3n indebida de las pruebas y no contra la omisi\u00f3n del Consejo en relaci\u00f3n con la pr\u00e1ctica de pruebas que podr\u00edan ser favorables a la actora. &nbsp; &nbsp;<\/p>\n<p>Partiendo de la base de que el Consejo Superior de la Judicatura s\u00ed reuni\u00f3 un conjunto probatorio amplio que daba espacio para fallar en uno u otro sentido, cabe ahora preguntarse si el camino por el que opt\u00f3 en el momento de la decisi\u00f3n puede ser objeto de reproche por parte de la Corte.&nbsp; &nbsp;<\/p>\n<p>Ahora bien, en el fallo no se observa que las pruebas que tuvieron a la postre mayor incidencia hayan sido asumidas en forma arbitraria. En efecto, en el aparte de las consideraciones se destina una p\u00e1gina a justificar por qu\u00e9 se le pod\u00eda adjudicar gran valor a los testimonios de los empleados del juzgado. Igualmente, el pronunciamiento se ocupa de las objeciones contra la declaraci\u00f3n del magistrado Esquivia. Asimismo, el Consejo manifiesta que no considera como una prueba importante el hecho de que no constara el nombre del Juez Tercero Penal Municipal en el libro de registro de visitantes al Consejo Seccional de la Judicatura. As\u00ed las cosas, y en raz\u00f3n de que no se advierten errores desmesurados en la ponderaci\u00f3n de las pruebas, la Corte no puede pasar a censurar el ejercicio valorativo que realiz\u00f3 el Consejo Superior de la Judicatura.&nbsp; &nbsp;<\/p>\n<p>D E C I S I O N &nbsp;<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Tercera de Revisi\u00f3n, &nbsp;<\/p>\n<p>R E S U E L V E: &nbsp;<\/p>\n<p>Primero: CONFIRMAR, por las razones expuestas en esta providencia, el fallo proferido por la Sala Penal del Tribunal Superior del Distrito Judicial de Bogot\u00e1, el d\u00eda veintiocho de agosto de 1996, y, en consecuencia, denegar la tutela solicitada por la ciudadana Marcia Fl\u00f3rez de Lozano.&nbsp; &nbsp;<\/p>\n<p>Segundo: L\u00edbrense por Secretar\u00eda las comunicaciones a que se refiere el art\u00edculo 36 del decreto 2591 de 1991.&nbsp; &nbsp;<\/p>\n<p>C\u00f3piese, notif\u00edquese, comun\u00edquese, ins\u00e9rtese en la Gaceta de la Corte Constitucional y c\u00famplase.&nbsp; &nbsp;<\/p>\n<p>EDUARDO CIFUENTES MU\u00d1OZ &nbsp;<\/p>\n<p>Magistrado Ponente &nbsp;<\/p>\n<p>CARLOS GAVIRIA DIAZ &nbsp;<\/p>\n<p>&nbsp;Magistrado &nbsp; &nbsp;<\/p>\n<p>JOSE GREGORIO HERNANDEZ GALINDO &nbsp;<\/p>\n<p>Magistrado &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; &nbsp;<\/p>\n<p>MARTHA VICTORIA SACHICA DE MONCALEANO&nbsp; &nbsp;<\/p>\n<p>Secretaria General &nbsp; &nbsp;<\/p>\n<p>(Sentencia aprobada por la Sala Tercera de Revisi\u00f3n, en la ciudad de Santa Fe de Bogot\u00e1, D.C., a los seis (6) d\u00edas del mes de Febrero de mil novecientos noventa y siete (1997). &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>T-055-97 &nbsp; &nbsp; Sentencia T-055\/97 &nbsp; VIA DE HECHO-Aplicaci\u00f3n excepcional &nbsp; La Corte ha precisado que la figura de la v\u00eda de hecho puede ser aplicada \u00fanicamente de manera excepcional, pues una intromisi\u00f3n permanente del juez constitucional en la esfera de las dem\u00e1s jurisdicciones, adem\u00e1s de propiciar un socavamiento de los \u00e1mbitos propios de cada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-3096","post","type-post","status-publish","format-standard","hentry","category-tutelas-1997"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/3096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=3096"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/3096\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=3096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=3096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=3096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}