{"id":3544,"date":"2024-05-30T17:43:22","date_gmt":"2024-05-30T17:43:22","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/05\/30\/c-276-98\/"},"modified":"2024-05-30T17:43:22","modified_gmt":"2024-05-30T17:43:22","slug":"c-276-98","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/c-276-98\/","title":{"rendered":"C 276 98"},"content":{"rendered":"<p>C-276-98<\/p>\n<p>&nbsp; &nbsp; Sentencia C-276\/98 &nbsp;<\/p>\n<p>COSA JUZGADA CONSTITUCIONAL &nbsp;<\/p>\n<p>Referencia: Expediente D-1896 &nbsp;<\/p>\n<p>Acci\u00f3n de inconstitucionalidad contra el Decreto 1675 de 1997 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; &nbsp;<\/p>\n<p>Actor: Ariel Luna Luna. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; &nbsp;<\/p>\n<p>Magistrado Ponente:&nbsp; &nbsp;<\/p>\n<p>Dr. CARLOS GAVIRIA &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; DIAZ. &nbsp;<\/p>\n<p>Santaf\u00e9 de Bogot\u00e1, D.C., junio tres (3) de mil novecientos noventa y ocho (1998) &nbsp;<\/p>\n<p>&nbsp;I. ANTECEDENTES&nbsp; &nbsp;<\/p>\n<p>El ciudadano Ariel Luna Luna, en ejercicio de la acci\u00f3n p\u00fablica de inconstitucionalidad, &nbsp;presenta demanda contra el Decreto 1675 de junio 27 de 1997 &#8220;Por el cual se suprime el Instituto de Mercadeo Agropecuario IDEMA y se ordena su liquidaci\u00f3n&#8221;, por infringir los art\u00edculos 6, 150-7-10, 151 y 336 de la Carta Pol\u00edtica. &nbsp;<\/p>\n<p>Cumplidos los tr\u00e1mites constitucionales y legales estatuidos para procesos de esta \u00edndole, procede la Corte a decidir.&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>II. NORMA ACUSADA &nbsp;<\/p>\n<p>El texto del decreto objeto de impugnaci\u00f3n, aparece publicado en el Diario Oficial No. 43072 del 27 de junio de 1997, cuyo texto no es necesario transcribir, dada la decisi\u00f3n que sobre \u00e9l habr\u00e1 de tomar la Corte.&nbsp; &nbsp;<\/p>\n<p>III. LA DEMANDA&nbsp; &nbsp;<\/p>\n<p>Considera el actor que el Gobierno se extralimit\u00f3 en el ejercicio de las facultades extraordinarias que le fueron conferidas en el art\u00edculo 30 de la ley 344 de 1996, pues procedi\u00f3 a suprimir y liquidar una empresa industrial y comercial del Estado, cual es el IDEMA, sin tener competencia para ello.&nbsp; &nbsp;<\/p>\n<p>En efecto, se\u00f1ala que el Presidente de la Rep\u00fablica no pod\u00eda suprimir y liquidar el IDEMA, por ser una empresa industrial y comercial del Estado, pues las facultades \u00fanicamente lo autorizaban para hacerlo respecto de entidades de la rama ejecutiva del orden nacional &#8220;siempre y cuando, la Constituci\u00f3n no les reconociera un r\u00e9gimen de autonom\u00eda como las que requieren autorizaci\u00f3n expresa para poder ser suprimidas&#8221;. Adem\u00e1s, dada su naturaleza el IDEMA goza de autonom\u00eda constitucional. &nbsp;<\/p>\n<p>IV. &nbsp;INTERVENCION CIUDADANA &nbsp; &nbsp;<\/p>\n<p>El liquidador del IDEMA, actuando por medio de apoderado, solicita a la Corte declarar exequible el Decreto 1675 de 1997, por estar acorde con los preceptos constitucionales y haberse expedido con pleno respeto de las facultades contenidas en el art\u00edculo 30 de la Ley 344 de 1996. &nbsp;<\/p>\n<p>En &nbsp;efecto, considera que el IDEMA es una entidad de la rama ejecutiva del orden nacional y, como tal, pod\u00eda ser objeto de supresi\u00f3n. &#8220;En consecuencia, y razonando en estricta l\u00f3gica jur\u00eddica, as\u00ed como de\u00f3nticamente, mal podr\u00eda un decreto que se circunscribe al mandato de una ley, resultar contrario a la ley ya declarada constitucional.&#8221; &nbsp;<\/p>\n<p>V. &nbsp;CONCEPTO DEL PROCURADOR GENERAL DE LA NACION &nbsp;<\/p>\n<p>Manifiesta el Procurador General de la Naci\u00f3n que sobre el caso materia de debate, ya emiti\u00f3 concepto dentro del proceso D-1858. En consecuencia, se limita a transcribir los argumentos que en esa oportunidad expuso para solicitar la declaraci\u00f3n de constitucionalidad del decreto 1675\/97, objeto de impugnaci\u00f3n. Y concluye, diciendo que si al momento de dictarse este fallo la Corte ya ha emitido pronunciamiento en el proceso precitado, deber\u00e1 estarse a lo all\u00ed resuelto. &nbsp;<\/p>\n<p>VI. CONSIDERACIONES DE LA CORTE &nbsp;<\/p>\n<p>a) Competencia &nbsp;<\/p>\n<p>Esta Corporaci\u00f3n es tribunal competente para decidir sobre la constitucionalidad del decreto acusado, de conformidad con lo dispuesto en el art\u00edculo 241-5 de la Constituci\u00f3n.&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;<\/p>\n<p>a. Cosa juzgada &nbsp; &nbsp;<\/p>\n<p>Mediante sentencia C-270 del 3 de junio de 1998, con ponencia del Magistrado Vladimiro Naranjo Mesa, esta Corporaci\u00f3n declar\u00f3 exequible el decreto 1675 de 1997 &#8220;Por el cual se suprime el Instituto de Mercadeo Agropecuario IDEMA y se ordena su liquidaci\u00f3n&#8221;, por no exceder el l\u00edmite material fijado en la ley de habilitaci\u00f3n legislativa, concretamente el art\u00edculo 30 de la ley 344 de 1996.&nbsp; &nbsp;<\/p>\n<p>Dado que en esta oportunidad se demanda el mismo ordenamiento por una de las razones analizadas por la Corte en el fallo precitado, se ordenar\u00e1 estar a lo all\u00ed resuelto, pues ha operado el fen\u00f3meno de la cosa juzgada constitucional (art. 243 C.P.) que impide a esta Corporaci\u00f3n volver sobre lo decidido. &nbsp; &nbsp;<\/p>\n<p>En m\u00e9rito de lo expuesto, la Corte Constitucional &nbsp;administrando justicia &nbsp;en nombre del pueblo y por mandato de la Constituci\u00f3n, &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;R E S U E L V E&nbsp;: &nbsp;<\/p>\n<p>ESTARSE A LO RESUELTO en la Sentencia C-270 del 3 de junio de 1998 (proceso D-1858). &nbsp;<\/p>\n<p>C\u00f3piese, notif\u00edquese, comun\u00edquese a quien corresponda, publ\u00edquese, ins\u00e9rtese en la Gaceta de la Corte Constitucional y arch\u00edvese el expediente. &nbsp; &nbsp;<\/p>\n<p>VLADIMIRO NARANJO MESA &nbsp;<\/p>\n<p>Presidente &nbsp;<\/p>\n<p>ANTONIO BARRERA CARBONELL &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>En comisi\u00f3n &nbsp;<\/p>\n<p>EDUARDO CIFUENTES MU\u00d1OZ &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>. &nbsp;<\/p>\n<p>CARLOS GAVIRIA DIAZ &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>JOSE GREGORIO HERNANDEZ GALINDO &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>&nbsp;HERNANDO HERRERA VERGARA &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>CARMENZA ISAZA DE GOMEZ &nbsp;<\/p>\n<p>Magistrada (E) &nbsp;<\/p>\n<p>ALEJANDRO MARTINEZ CABALLERO &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>FABIO MORON DIAZ &nbsp;<\/p>\n<p>Magistrado&nbsp; &nbsp;<\/p>\n<p>MARTHA VICTORIA SACHICA DE MONCALEANO &nbsp;<\/p>\n<p>Secretaria General &nbsp;<\/p>\n<p>LA SUSCRITA SECRETARIA GENERAL DE LA CORTE CONSTITUCIONAL, HACE CONSTAR QUE: &nbsp;<\/p>\n<p>El H. Magistrado doctor Antonio Barrera Carbonell, no suscribe la presente providencia, por encontrarse en comisi\u00f3n oficial en el exterior. &nbsp;<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA DE MONCALEANO &nbsp;<\/p>\n<p>Secretaria General &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>C-276-98 &nbsp; &nbsp; Sentencia C-276\/98 &nbsp; COSA JUZGADA CONSTITUCIONAL &nbsp; Referencia: Expediente D-1896 &nbsp; Acci\u00f3n de inconstitucionalidad contra el Decreto 1675 de 1997 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; &nbsp; Actor: Ariel Luna Luna. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-3544","post","type-post","status-publish","format-standard","hentry","category-sentencias-1998"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/3544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=3544"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/3544\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=3544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=3544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=3544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}