{"id":4571,"date":"2024-05-30T18:04:17","date_gmt":"2024-05-30T18:04:17","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/05\/30\/t-027-99\/"},"modified":"2024-05-30T18:04:17","modified_gmt":"2024-05-30T18:04:17","slug":"t-027-99","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-027-99\/","title":{"rendered":"T 027 99"},"content":{"rendered":"<p>T-027-99<\/p>\n<p>&nbsp; &nbsp; Sentencia T-027\/99 &nbsp;<\/p>\n<p>ACCION DE TUTELA-Carencia actual de objeto &nbsp;<\/p>\n<p>La acci\u00f3n de tutela est\u00e1 encaminada a obtener la protecci\u00f3n efectiva de los derechos fundamentales, cuando los mismos se encuentran amenazados o vulnerados por las autoridades p\u00fablicas, o por los particulares, en los casos previstos por la ley. En consecuencia, la protecci\u00f3n ofrecida por la acci\u00f3n de tutela pierde sentido, por innecesaria, cuando durante el curso del proceso desaparece la amenaza o cesa la vulneraci\u00f3n. El juez queda inhabilitado, por tanto, para emitir orden alguna tendiente a restablecer el orden jur\u00eddico quebrantado, porque \u00e9ste ha recobrado su normalidad sin la intervenci\u00f3n de la autoridad del Estado.&nbsp; &nbsp;<\/p>\n<p>SENTENCIA DE REVISION DE TUTELA-Carencia actual de objeto no exime pronunciamiento de fondo &nbsp;<\/p>\n<p>SENTENCIA DE REVISION DE TUTELA-Pedagog\u00eda constitucional &nbsp;<\/p>\n<p>DERECHO A LA SALUD-Car\u00e1cter prestacional &nbsp;<\/p>\n<p>DERECHO A LA SALUD-Fundamental por conexidad &nbsp;<\/p>\n<p>DERECHO A LA SALUD-Requisitos para la protecci\u00f3n por tutela &nbsp;<\/p>\n<p>DERECHO A LA SALUD-Pr\u00e1ctica de examen o procedimiento cl\u00ednico no urgente &nbsp;<\/p>\n<p>PREVENCION EN TUTELA-Dilaci\u00f3n injustificada de prestaci\u00f3n del servicio de salud &nbsp;<\/p>\n<p>Referencia: Expediente T-181489 &nbsp;<\/p>\n<p>Peticionario: Mar\u00eda Elayne Lozano de Arenas. &nbsp;<\/p>\n<p>Procedencia: Tribunal Superior de Popay\u00e1n. &nbsp;&nbsp; &nbsp;<\/p>\n<p>Magistrado Ponente: &nbsp;<\/p>\n<p>Dr. VLADIMIRO NARANJO MESA &nbsp;<\/p>\n<p>Santaf\u00e9 de Bogot\u00e1, D.C., &nbsp;veinticinco (25) de enero de mil novecientos noventa y nueve (1999). &nbsp;<\/p>\n<p>La Sala Novena de Revisi\u00f3n de la Corte Constitucional, conformada por los Magistrados Vladimiro Naranjo Mesa -Presidente de la Sala-, Alfredo Beltr\u00e1n Sierra y Antonio Barrera Carbonell, ha pronunciado la siguiente: &nbsp;<\/p>\n<p>SENTENCIA &nbsp;<\/p>\n<p>en el proceso de tutela radicado bajo el n\u00famero T-181489, adelantado por la se\u00f1ora &nbsp;Maria Elayne Lozano de Arenas, contra el Instituto de Seguros Sociales -Seccional Popay\u00e1n-.&nbsp; &nbsp;<\/p>\n<p>I. ANTECEDENTES &nbsp;<\/p>\n<p>De acuerdo con lo dispuesto en los art\u00edculos 86 de la Constituci\u00f3n Pol\u00edtica y 33 del Decreto 2591 de 1991, la Sala de Selecci\u00f3n N\u00famero Diez de la Corte Constitucional escogi\u00f3 para efectos de su revisi\u00f3n, mediante Auto del 2 de octubre de 1998, la acci\u00f3n de tutela de la referencia. &nbsp;<\/p>\n<p>De conformidad con el art\u00edculo 34 del Decreto 2591 de 1991, esta Sala de Revisi\u00f3n procede a dictar la sentencia correspondiente. &nbsp;<\/p>\n<p>1. Solicitud &nbsp;<\/p>\n<p>La demandante, Maria Elayne Lozano de Arenas, &nbsp;solicita la protecci\u00f3n de sus derechos fundamentales a la salud y a la vida, &nbsp;presuntamente vulnerados por la Seccional de Popay\u00e1n del Instituto de Seguros Sociales&nbsp; &nbsp;<\/p>\n<p>2. Hechos &nbsp;<\/p>\n<p>La se\u00f1ora &nbsp;Lozano de Arenas present\u00f3 demanda de tutela en contra del Instituto de Seguros Sociales (I.S.S.) -Seccional Popay\u00e1n-, por cuanto dicha instituci\u00f3n le ven\u00eda dilatando la atenci\u00f3n m\u00e9dica requerida, a pesar de sus graves padecimientos de salud. &nbsp;<\/p>\n<p>Seg\u00fan la demandante, el 23 de junio del a\u00f1o en curso su m\u00e9dico tratante le orden\u00f3 un examen de \u201ccolon por enema\u201d, pues desde hace m\u00e1s de dos a\u00f1os viene sufriendo problemas intestinales. El I.S.S., entidad a la que recurri\u00f3 en primera instancia, la remiti\u00f3 al hospital Universitario de San Jos\u00e9, donde no la atendieron porque la disponibilidad de las planillas s\u00f3lo era para ex\u00e1menes urgentes o para &nbsp;personas hospitalizadas. &nbsp;<\/p>\n<p>Posteriormente acudi\u00f3 a la Cl\u00ednica Santillana, donde tambi\u00e9n le negaron los ex\u00e1menes por cuanto el Gerente del I.S.S. hab\u00eda dado la orden de recibir \u00fanicamente casos urgentes. El m\u00e9dico tratante, a su vez, le manifest\u00f3 la imposibilidad de calificar el examen como urgente, pues seg\u00fan las directivas del I.S.S., estaba reservado exclusivamente para personas hospitalizadas. &nbsp;<\/p>\n<p>La actora aduce que la demora en la prestaci\u00f3n de los servicios m\u00e9dicos requeridos le afectan su salud, ya que permanece con un dolor continuo junto a la \u201cingle del lado derecho\u201d. Adem\u00e1s de lo anterior, se le formul\u00f3 un medicamento para los ojos denominado \u201calcohol-polivinilico alvasol\u201d, que la demandada tampoco le ha entregado con la excusa de que est\u00e1 agotado. &nbsp;<\/p>\n<p>3. Pretensiones &nbsp;<\/p>\n<p>La accionante solicita la pr\u00e1ctica del examen y la entrega de las gotas para el problema ocular. &nbsp;<\/p>\n<p>4. Argumentos del I.S.S. &nbsp;<\/p>\n<p>Seg\u00fan el representante judicial del I.S.S., la entidad no ha tenido la intenci\u00f3n de negarle el examen a la tutelante, sino que lo ha sometido a la condici\u00f3n de que previamente se cumpla con ciertos requisitos cl\u00ednicos y administrativos establecidos en los reglamentos, dado que la exploraci\u00f3n m\u00e9dica que requiere la peticionaria no es urgente. &nbsp;<\/p>\n<p>II. ACTUACION JUDICIAL &nbsp;<\/p>\n<p>1. Unica instancia &nbsp;<\/p>\n<p>El Tribunal Superior del Distrito Judicial del Cauca, mediante providencia del 26 de agosto de 1998, neg\u00f3 la acci\u00f3n de tutela instaurada por la se\u00f1ora Lozano de Arenas por considerar que, no obstante se observaba en el Instituto demandado una protuberante falta de eficiencia al dilatar la pr\u00e1ctica de un examen, so pretexto de no haberse calificado como urgente, la actora pod\u00eda insistir ante la accionada para que se le prestara el servicio lo antes posible, as\u00ed como tambi\u00e9n pod\u00eda quejarse ante la Superintendencia Nacional de Salud por la ineficiencia del Instituto.&nbsp; &nbsp;<\/p>\n<p>III. CONSIDERACIONES DE LA SALA &nbsp;<\/p>\n<p>1. Competencia &nbsp;<\/p>\n<p>De conformidad con lo establecido en los art\u00edculos 86 y 241, numeral 9o. de la Constituci\u00f3n Pol\u00edtica y 31 a 36 del Decreto 2591 de 1991, la Sala Novena de Revisi\u00f3n de la Corte Constitucional es competente para revisar el fallo de tutela de la referencia. &nbsp;<\/p>\n<p>2.- Pruebas solicitadas por la Sala Novena de Revisi\u00f3n&nbsp; &nbsp;<\/p>\n<p>Repartido el expediente, la Sala Novena de Revisi\u00f3n encontr\u00f3 que los elementos de juicio aportados al mismo eran insuficientes para esclarecer las circunstancias en las que actualmente se hallaba el proceso.&nbsp; &nbsp;<\/p>\n<p>Por ello, mediante Auto del 6 de octubre de 1998, &nbsp;la Sala solicit\u00f3 al gerente del &nbsp;Instituto de Seguros Sociales en Popay\u00e1n que informar\u00e1 si le hab\u00eda sido practicado el examen de \u201ccolon por enema\u201d a la solicitante. Adicionalmente, se le pidi\u00f3 que aclarara las circunstancias por las cuales el medicamento formulado para aliviar la aflicci\u00f3n que la misma viene padeciendo en los ojos no hab\u00eda sido suministrado. &nbsp;<\/p>\n<p>La entidad demandada inform\u00f3 a la Corte Constitucional que la se\u00f1ora Maria Elayne Lozano de Arenas ten\u00eda lista la orden para el examen requerido y que estaba en turno de espera para su ejecuci\u00f3n en la Cl\u00ednica Santillana, ya que el Seguro no ten\u00eda los equipos para tal procedimiento. Respecto del medicamento formulado, se autoriz\u00f3 su entrega en una farmacia Comercial por no estar disponible en la del I.S.S. &nbsp;<\/p>\n<p>Posteriormente, en contestaci\u00f3n al Auto del 25 de noviembre, por el cual esta Sala volvi\u00f3 a solicitar informaci\u00f3n al I.S.S. y a la Cl\u00ednica Santillana con el fin de determinar la efectiva pr\u00e1ctica del examen de la solicitante, el I.S.S. manifest\u00f3 que a la paciente se le realiz\u00f3 el examen el d\u00eda 16 de diciembre de 1998 en el Hospital San Jos\u00e9 (folio 122). &nbsp;<\/p>\n<p>3. Consecuencias de la acci\u00f3n de tutela cuando durante su curso el hecho que la gener\u00f3, fue superado. &nbsp;<\/p>\n<p>La acci\u00f3n de tutela est\u00e1 encaminada a obtener la protecci\u00f3n efectiva de los derechos fundamentales, cuando los mismos se encuentran amenazados o vulnerados por las autoridades p\u00fablicas, o por los particulares, en los casos previstos por la ley. En consecuencia, la protecci\u00f3n ofrecida por la acci\u00f3n de tutela pierde sentido, por innecesaria, cuando durante el curso del proceso desaparece la amenaza o cesa la vulneraci\u00f3n. El juez queda inhabilitado, por tanto, para emitir orden alguna tendiente a restablecer el orden jur\u00eddico quebrantado, porque \u00e9ste ha recobrado su normalidad sin la intervenci\u00f3n de la autoridad del Estado.&nbsp; &nbsp;<\/p>\n<p>No obstante, es jurisprudencia de la Corte Constitucional que cuando el hecho motivo de la acci\u00f3n desaparece durante el curso de la tutela y las circunstancias particulares del conflicto original as\u00ed lo ameritan, la Corporaci\u00f3n puede pronunciarse sobre el caso sometido a revisi\u00f3n. En efecto, la Corte ha avalado esta pr\u00e1ctica, consciente de la funci\u00f3n que tiene como promotor de la pedagog\u00eda constitucional y tribunal encargado de precisar, reforzar y acendrar la jurisprudencia.1. &nbsp;<\/p>\n<p>Con esta advertencia, y teniendo en cuenta que en el caso bajo examen el hecho generador de la demanda ya fue superado, pues se practic\u00f3 el examen requerido por la demandante y los medicamentos ya fueron entregados, esta Sala considera necesario pronunciarse a t\u00edtulo ilustrativo sobre el caso objeto de debate, con el fin de precisar los criterios jur\u00eddicos que debieron tenerse en cuenta a la hora de resolver el conflicto planteado. &nbsp;<\/p>\n<p>4. El derecho a la salud&nbsp; &nbsp;<\/p>\n<p>A la luz del art\u00edculo 49 de la Constituci\u00f3n Pol\u00edtica, el Estado tiene la obligaci\u00f3n de garantizar a todas las personas \u201cel acceso a los servicios de promoci\u00f3n, protecci\u00f3n y recuperaci\u00f3n de la salud\u201d. En consecuencia, los particulares est\u00e1n facultados para exigir del Estado el cumplimiento efectivo de dicha obligaci\u00f3n, con el fin de que \u00e9ste ejecute actividades concretas encaminadas a proveer los medios necesarios para su sostenimiento. Esa facultad de exigencia en favor de los particulares, es la que permite catalogar el derecho a la salud, y junto con \u00e9l, el de la seguridad social, como derechos de car\u00e1cter prestacional.2&nbsp; &nbsp;<\/p>\n<p>Adicionalmente, el derecho a la salud ostenta una dimensi\u00f3n program\u00e1tica: su plena garant\u00eda constituye, m\u00e1s que una realidad actual, una objetivo pol\u00edtico y un compromiso derivado de la estructura del &nbsp;Estado Social de Derecho. Es un prop\u00f3sito del Estado por el cual \u00e9ste busca totalizar la efectiva atenci\u00f3n de los usuarios, de acuerdo con las posibilidades t\u00e9cnicas, econ\u00f3micas, geogr\u00e1ficas e hist\u00f3ricas de la realidad nacional.&nbsp; &nbsp;<\/p>\n<p>A pesar de dichas caracter\u00edsticas, como lo ha reconocido la Corte, el derecho a la salud no tiene por s\u00ed mismo rango fundamental, salvo cuando est\u00e1 en conexi\u00f3n inescindible con el derecho a la vida o a la integridad f\u00edsica. Sin embargo, ya que su naturaleza tiene tan \u00edntima relaci\u00f3n con \u00e9ste y otros, pues la conservaci\u00f3n de la salud es la que permite, en mayor o menor grado, el pleno goce de las potencialidades individuales, la Corte Constitucional ha reconocido que \u00e9ste derecho puede llegar a adquirir rango fundamental por el citado factor de conexidad.3 &nbsp;<\/p>\n<p>Sobre el particular, ha dicho la Corte: &nbsp;<\/p>\n<p>\u201cTodo lo anterior permite concluir que en la Constituci\u00f3n de 1.991 la salud de los colombianos es -por conexidad- un derecho fundamental cuya efectividad corresponde en buena medida garantizar al Estado, tomando muy en cuenta las espec\u00edficas necesidades de su titular y los recursos existentes para satisfacerlas. &nbsp;<\/p>\n<p>\u201cLa salud es uno de aquellos derechos que por su car\u00e1cter inherente a la existencia de todo ser humano se encuentra protegido en nuestro ordenamiento, especialmente en aras de una igualdad real, en las personas que por su condici\u00f3n econ\u00f3mica, f\u00edsica o mental se hallen en circunstancias de debilidad manifiesta. Este derecho busca adem\u00e1s, y en forma primordial, el aseguramiento del derecho fundamental a la vida, por lo que su naturaleza asistencial impone un tratamiento prioritario y preferencial por parte del gobierno y del legislador, en procura de su efectiva protecci\u00f3n.\u201d (Sentencia T-571\/92 M.P. Dr Jaime San\u00edn Greiffenstein) &nbsp;<\/p>\n<p>Atendiendo a las consideraciones y requisitos se\u00f1alados anteriormente, debe esta Sala de Revisi\u00f3n entrar a resolver si, en el caso concreto, era viable conceder por v\u00eda de tutela la protecci\u00f3n solicitada por la demandante. &nbsp;<\/p>\n<p>5. An\u00e1lisis del caso concreto &nbsp;<\/p>\n<p>En primer lugar, no hay duda de la vinculaci\u00f3n que la se\u00f1ora Lozano de Arenas ten\u00eda con el Instituto de los Seguros Sociales -E.P.S.-, en calidad de afiliada al Plan Obligatorio de Salud, pues as\u00ed se desprende de la historia cl\u00ednica adosada al expediente y del reconocimiento que del mismo hecho hizo el representante judicial de la entidad demandada ante el juez de primera instancia (folio 89). &nbsp;<\/p>\n<p>Por esta raz\u00f3n, la peticionaria ten\u00eda derecho a recibir en su integridad el servicio requerido para detectar la causa de sus padecimientos, que para el caso particular eran el examen de colon por enema, ordenado por su m\u00e9dico tratante, y las gotas para su deficiencia ocular. &nbsp;<\/p>\n<p>Resuelto este punto, corresponde ahora determinar si en el caso sub lite, la salud se encontraba en conexi\u00f3n con un derecho de rango fundamental, lo que en \u00faltimas implica analizar las posibles consecuencias que su vulneraci\u00f3n podr\u00eda generar en el derecho a la integridad f\u00edsica o a la vida.&nbsp; &nbsp;<\/p>\n<p>Para el efecto, sea lo primero decir que el I.S.S. advirti\u00f3 en la contestaci\u00f3n de la demanda que, al no haber calificado el m\u00e9dico tratante como urgente la auscultaci\u00f3n requerida por la paciente, \u00e9sta deb\u00eda esperar su turno en uno de los centros de atenci\u00f3n al usuario, pues tal era el tr\u00e1mite previsto en los reglamentos para este tipo de procedimientos.&nbsp; &nbsp;<\/p>\n<p>Ahora bien, es necesario aclarar que la calificaci\u00f3n de urgencia de un examen terap\u00e9utico corresponde hacerla al m\u00e9dico tratante, pues \u00e9ste es quien conoce como ninguno las condiciones f\u00edsicas del paciente y puede determinar la perentoriedad o no del an\u00e1lisis cient\u00edfico. A su vez, dicho concepto sirve de base a la entidad prestadora del servicio para ordenar la ejecuci\u00f3n inmediata de la exploraci\u00f3n m\u00e9dica, si esta es urgente, o en caso contrario, para someter al usuario al tr\u00e1mite ordinario de atenci\u00f3n previsto en los reglamentos, ya que en tales eventos se impone la necesidad de evacuar la demanda de atenci\u00f3n en orden estricto de solicitudes. Resulta evidente que si la asistencia m\u00e9dica se concede de manera indiscriminada, sin atender a las prioridades de los pacientes m\u00e1s graves y sin respetar los ordenes de solicitud en las consultas, el sistema de salud entrar\u00eda en caos y no podr\u00eda cumplir con las metas de eficiencia y universalidad que se ha propuesto. &nbsp;<\/p>\n<p>No obstante, el hecho de que un examen o un procedimiento cl\u00ednico no sea urgente, no autoriza a la entidad para evadir de manera indefinida la atenci\u00f3n del enfermo, pues la dilaci\u00f3n injustificada podr\u00eda agravar el padecimiento y, eventualmente, llevar la enfermedad a l\u00edmites inmanejables donde la recuperaci\u00f3n podr\u00eda resultar m\u00e1s gravosa o incierta, comprometiendo la integridad personal e, incluso, la vida del afectado. En consecuencia, es obligaci\u00f3n de la entidad prestadora del servicio, adelantar las gestiones en el menor tiempo posible para que el usuario no padezca el rigor de su mal, m\u00e1s all\u00e1 de lo estrictamente imprescindible. &nbsp;<\/p>\n<p>Valga entonces lo dicho para concluir, en el caso concreto, que si bien la falta de atenci\u00f3n inmediata de la se\u00f1ora Lozano de Arenas no constituy\u00f3 violaci\u00f3n del derecho invocado, porque cuando el examen fue ordenado su estado salud no pon\u00eda en peligro los derechos fundamentales a la integridad f\u00edsica y a la vida, s\u00ed lo fue el retardo injustificado de la entidad demandada, pues a pesar de que el galeno expidi\u00f3 la orden el 23 de junio de 1998, la misma no se hab\u00eda hecho efectiva a la fecha de interposici\u00f3n de la demanda, sino que lo fue 6 meses despu\u00e9s, el 16 de diciembre del mismo a\u00f1o. &nbsp;<\/p>\n<p>Esta Sala de Revisi\u00f3n observa que el tiempo que medi\u00f3 entre la remisi\u00f3n de la paciente y la fecha de ejecuci\u00f3n final del examen, no se aviene a los t\u00e9rminos racionales y efectivos que, seg\u00fan reiterada jurisprudencia de esta Corporaci\u00f3n, deben reglar la prestaci\u00f3n del servicio de salud. &nbsp;<\/p>\n<p>De todo lo dicho se tiene que, a pesar de haber sido superado el hecho motivo de la tutela, porque ya se practic\u00f3 el procedimiento y se entreg\u00f3 el medicamento ocular requerido, la obligaci\u00f3n del I.S.S. era la de proveer la atenci\u00f3n de manera pronta y oportuna a la solicitante, por lo que la instituci\u00f3n merece una prevenci\u00f3n por parte de esta Corte para que en lo sucesivo no vuelva a incurrir en la misma conducta con otros usuarios, evitando as\u00ed la eventual violaci\u00f3n de sus derechos constitucionales fundamentales. &nbsp;<\/p>\n<p>En consecuencia, esta Sala de Revisi\u00f3n confirmar\u00e1 la sentencia proferida por el juez de \u00fanica instancia, que decidi\u00f3 negar la tutela en cuesti\u00f3n, pero por las razones expuestas en esta providencia, pues ya fue superado el hecho que dio origen a la demanda. En este sentido, la Corte Constitucional prevendr\u00e1, pues, al Instituto demandado para que tenga en cuenta las consideraciones contenidas en la parte motiva de esta providencia y se abstenga de dilatar injustificadamente la prestaci\u00f3n del servicio de salud a sus usuarios. &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>DECISION &nbsp;<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Novena de Revisi\u00f3n &nbsp;de la Corte Constitucional, en nombre del pueblo y por mandato de la Constituci\u00f3n, &nbsp; &nbsp;<\/p>\n<p>&nbsp;R E S U E L V E : &nbsp;<\/p>\n<p>Primero: CONFIRMAR, pero por las razones expuestas en la parte motiva de esta providencia, la sentencia proferida en \u00fanica instancia el 26 de agosto de 1998 por el Tribunal Superior del Distrito Judicial del Cauca &#8211; Sala de Tutela-, que decidi\u00f3 no conceder la demanda presentada por la se\u00f1ora Maria Elayne Lozano de Arenas, en contra del Instituto de Seguro Social &#8211; seccional Popay\u00e1n-. &nbsp;<\/p>\n<p>Segundo: PREVENIR al Instituto de Seguros Sociales &#8211; seccional Popay\u00e1n- para que en lo sucesivo y atendiendo a las consideraciones consignadas en esta providencia, se abstenga de dilatar injustificadamente la prestaci\u00f3n del servicio de salud a los afiliados que lo soliciten. &nbsp;<\/p>\n<p>C\u00f3piese, notif\u00edquese, ins\u00e9rtese en la gaceta de la Corte Constitucional y c\u00famplase. &nbsp;<\/p>\n<p>VLADIMIRO NARANJO MESA &nbsp;<\/p>\n<p>Magistrado sustanciador &nbsp;<\/p>\n<p>ANTONIO BARRERA CARBONELL &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>ALFREDO BELTRAN SIERRA &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>MARTHA VICTORIA SACHICA DE MONCALEANO &nbsp;<\/p>\n<p>Secretaria General &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp;<\/p>\n<p>1 Cfr. Sentencia T-428\/98 M.P. Dr. Vladimiro Naranjo Mesa &nbsp;<\/p>\n<p>2 Sentencia T-571\/92 M.P. Dr. Jaime San\u00edn Greiffenstein &nbsp;<\/p>\n<p>3 \u201cLos derechos fundamentales por conexidad son aquellos que no siendo denominados como tales en el texto constitucional, sin embargo, les es comunicada esta calificaci\u00f3n en virtud de la \u00edntima e inescindible relaci\u00f3n con otros derechos fundamentales, de forma que si no fueron protegidos en forma inmediata los primeros se ocasionar\u00eda la vulneraci\u00f3n o amenaza de los segundos. &nbsp;Es el caso de la salud, que no siendo en principio derecho fundamental, adquiere esta categor\u00eda cuando la desatenci\u00f3n del enfermo amenaza con poner en peligro su derecho a la vida\u201d (Sentencia T-571\/92 ;.P. Dr. Jaime San\u00edn Greiffenstein) Cfr. adem\u00e1s, &nbsp;la Sentencia T-116\/93, M.P. Dr Hernando Herrera Vergara, &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>T-027-99 &nbsp; &nbsp; Sentencia T-027\/99 &nbsp; ACCION DE TUTELA-Carencia actual de objeto &nbsp; La acci\u00f3n de tutela est\u00e1 encaminada a obtener la protecci\u00f3n efectiva de los derechos fundamentales, cuando los mismos se encuentran amenazados o vulnerados por las autoridades p\u00fablicas, o por los particulares, en los casos previstos por la ley. En consecuencia, la protecci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-4571","post","type-post","status-publish","format-standard","hentry","category-tutelas-1999"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/4571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=4571"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/4571\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=4571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=4571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=4571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}