{"id":7858,"date":"2024-05-31T14:36:21","date_gmt":"2024-05-31T14:36:21","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/2024\/05\/31\/t-752-01\/"},"modified":"2024-05-31T14:36:21","modified_gmt":"2024-05-31T14:36:21","slug":"t-752-01","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/t-752-01\/","title":{"rendered":"T-752-01"},"content":{"rendered":"\n<p>\u00a0 \u00a0 Sentencia T-752\/01 \u00a0<\/p>\n<p>IUS VARIANDI-Alcance\/IUS VARIANDI-L\u00edmites \u00a0<\/p>\n<p>ACCION DE TUTELA-No es necesaria para cuestionar el ius variandi \u00a0<\/p>\n<p>TRASLADO DE EMPLEADO DEL DAS-Empleador dispuso los medios necesarios \u00a0<\/p>\n<p>ACCION DE TUTELA-Inexistencia de perjuicio irremediable \u00a0<\/p>\n<p>Reiteraci\u00f3n de Jurisprudencia \u00a0<\/p>\n<p>Referencia: expediente T-440655 \u00a0<\/p>\n<p>Acci\u00f3n de tutela instaurada por Marlene M\u00e1rquez Illidge contra el Departamento Administrativo de Seguridad D.A.S. \u00a0<\/p>\n<p>Magistrado Ponente: \u00a0<\/p>\n<p>Dr. RODRIGO ESCOBAR GIL \u00a0<\/p>\n<p>Bogot\u00e1 D.C., a los diecisiete (17) d\u00edas del mes de julio de dos mil uno (2001). \u00a0<\/p>\n<p>La Sala Quinta de Revisi\u00f3n de la Corte Constitucional, integrada por los Magistrados MARCO GERARDO MONROY CABRA, EDUARDO MONTEALEGRE LYNETT y RODRIGO ESCOBAR GIL, en ejercicio de sus competencias constitucionales y legales, ha proferido la siguiente: \u00a0<\/p>\n<p>SENTENCIA \u00a0<\/p>\n<p>Dentro del proceso de revisi\u00f3n de los fallos proferidos por la Sala Civil \u2013 Familia del Tribunal Superior de Santa Marta y por la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia, en el tr\u00e1mite del proceso de la referencia. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. ANTECEDENTES. \u00a0 \u00a0<\/p>\n<p>La accionante se encuentra vinculada al Departamento Administrativo de Seguridad D.A.S., desde el 15 de febrero de 1991, desempe\u00f1\u00e1ndose inicialmente en el cargo de Auxiliar de Inteligencia 204-07, y actualmente 204-13. Sus servicios los prestaba en la ciudad de Bogot\u00e1, pero a ra\u00edz del asesinato de su esposo en esta ciudad en el a\u00f1o de 1992, fue trasladada en el a\u00f1o de 1994 a la ciudad de Santa Marta, de donde es oriunda, y en donde se encuentra radicada toda su familia. De su uni\u00f3n marital tiene actualmente dos (2) hijos1. El 1\u00b0 de diciembre de 1999 fue ordenado su traslado a la Seccional del D.A.S. en el Departamento del Meta. \u00a0<\/p>\n<p>Ante la necesidad de conservar su trabajo -\u00fanica fuente de recursos econ\u00f3micos que le permiten, como mujer cabeza de familia, suplir las necesidades b\u00e1sicas de ella y de sus hijos- y en vista de la enorme distancia a donde iba a ser trasladada, logr\u00f3 que su madre y una de sus hermanas se trasladaran a Bogot\u00e1, a efectos de que estuvieran al cuidado de sus dos (2) hijos. Si bien dicha situaci\u00f3n facilit\u00f3 inicialmente el contacto con los menores, s\u00f3lo su hermana pudo permanecer por m\u00e1s tiempo al cuidado de sus hijos, gracias a que comenz\u00f3 a laborar en la Polic\u00eda Nacional. Sin embargo, en \u00e9ste momento el contrato de trabajo de su hermana se termin\u00f3 y se hace inminente el traslado de ella y de sus hijos a Santa Marta, pues a la actora le resulta muy dif\u00edcil seguir manteniendo los gastos de estas tres personas en la ciudad de Bogot\u00e1 (vivienda, servicios p\u00fablicos, alimentaci\u00f3n, estudio, vestido, etc.).\u00a0 \u00a0<\/p>\n<p>Sobre el particular indica igualmente, que posee una vivienda de su propiedad en la ciudad de Santa Marta, la cual presenta mora en el pago de su obligaci\u00f3n hipotecaria con Granahorrar. \u00a0<\/p>\n<p>Por otra parte se\u00f1ala, que las visitas que realiza a su hijos, se han venido dilatando en el tiempo, pues inicialmente eran cada ocho o quince d\u00edas, pero en la actualidad, la dificultad para obtener las autorizaciones correspondientes, han llevado a que dichas visitas se hagan cada mes. De esta manera, la unidad familiar se ha deteriorado al punto que esto ha generado problemas de comportamiento en sus hijos, y a ella la ha afectado en su salud, pues seg\u00fan ex\u00e1menes m\u00e9dicos a ella practicados, padece en la actualidad de Artritis Reumatoidea Vs Vasculitis L\u00fapica, enfermedad que requiere niveles m\u00ednimos de estr\u00e9s y un clima sano para su recuperaci\u00f3n. Esta \u00faltima situaci\u00f3n no es viable en el lugar en que se encuentra laborando, pues el clima es malsano, situaci\u00f3n que la actora demuestra con el desprendible de pago de su salario en donde se determina el pago de una \u201cPrima de Clima\u201d. \u00a0<\/p>\n<p>Finalmente, se\u00f1ala que las labores de inteligencia que ella cumple en dicha seccional del D.A.S., la mantienen en inminente peligro, debiendo circular por zonas de alto riesgo, y sumado al hecho de que por su dif\u00edcil situaci\u00f3n econ\u00f3mica debi\u00f3 trasladar su residencia a las propias instalaciones del D.A.S., temiendo por cualquier tipo de atentado, y manteniendo el mismo nivel \u00a0riesgos sobre su vida. \u00a0<\/p>\n<p>En vistas de las anteriores consideraciones, la accionante solicita la protecci\u00f3n de sus derechos fundamentales a la vida, a la igualdad, al trabajo en condiciones dignas y justas, a la unidad familiar, a la protecci\u00f3n especial a la mujer cabeza de familia, a la seguridad social, a la protecci\u00f3n de la ni\u00f1ez y a un ambiente sano. Para ello pide que se ordene al Director General del Departamento Administrativo de Seguridad D.A.S., para que ordene o autorice su traslado inmediato a la ciudad de Santa Marta, o en su defecto a Barranquilla, en raz\u00f3n a las circunstancias por ella expuestas. \u00a0<\/p>\n<p>En escrito remitido por el Coronel Germ\u00e1n Gustavo Jaramillo Piedrahita, Director General del Departamento Administrativo de Seguridad D.A.S. al juez de primera instancia, expuso algunas consideraciones con las cuales pretende demostrar la no vulneraci\u00f3n de derecho fundamental alguno. \u00a0<\/p>\n<p>Sobre el particular se\u00f1al\u00f3 lo siguiente: \u00a0<\/p>\n<p>\u201c&#8230; la administraci\u00f3n cuenta con la facultad de ubicar a sus funcionarios en aquellos lugares donde se requiera la prestaci\u00f3n del servicio p\u00fablico encomendado a la Entidad. As\u00ed, esta Direcci\u00f3n orden\u00f3 por medio de la Resoluci\u00f3n No. 01778 del 30 de noviembre de 1999, trasladar a la funcionaria Marlene de Jes\u00fas M\u00e1rquez Illidge, de la Seccional DAS Magdalena a la Seccional DAS Meta. \u00a0<\/p>\n<p>\u201cPor expreso mandato legal, estas determinaciones sobre el personal que labora en el Departamento Administrativo de Seguridad se deben adoptar unilateralmente, toda vez que de no ser ello as\u00ed, se afectar\u00eda ostensiblemente el servicio p\u00fablico. Veamos lo consagrado en el art\u00edculo 11 del Decreto 2146 de 1989 que se\u00f1ala: \u00a0<\/p>\n<p>\u2018Los movimientos de personal se efectuar\u00e1n por medio de traslado, encargo, ascenso y destinaci\u00f3n.\u2019 \u00a0<\/p>\n<p>\u201cEn concordancia con lo anterior, el art\u00edculo 5\u00ba del Decreto 597 de 1993 establece: \u00a0<\/p>\n<p>\u2018El personal del Departamento Administrativo de Seguridad podr\u00e1 ser trasladado a cualquiera de las dependencias de la instituci\u00f3n en el pa\u00eds, seg\u00fan lo exijan las necesidades y conveniencias del servicio. (Subrayado y Negrillas fuera del texto.\u2019 \u00a0<\/p>\n<p>\u2018Los empleados del Departamento Administrativo de Seguridad cuando por razones del servicio sean trasladados \u00a0o destinados con car\u00e1cter permanente a un lugar del pa\u00eds diferente de su sede habitual de los \u00faltimos seis meses y, por lo tanto, tengan que trasladar a su c\u00f3nyuge o compa\u00f1ero (a) permanente, hijos y padres que dependan econ\u00f3micamente de ellos a su nuevo lugar de trabajo, tendr\u00e1n derecho a percibir una prima de instalaci\u00f3n equivalente a treinta (30) d\u00edas de su asignaci\u00f3n b\u00e1sica mensual. Los empleados que no trasladen su familia s\u00f3lo tendr\u00e1n derecho a percibir, como prima de instalaci\u00f3n, diez (10) d\u00edas de su asignaci\u00f3n b\u00e1sica mensual. (Negrilla fuera del texto\u2019.\u201d \u00a0<\/p>\n<p>De igual forma menciona varias sentencias proferidas por la Corte Constitucional en las cuales se establece que hay ciertos organismos y entidades de la administraci\u00f3n que cuentan con una mayor discrecionalidad en materia de traslados de su personal, a fin de lograr el correcto desarrollo de la funci\u00f3n a ella asignada. Igualmente manifiesta el Director General del D.A.S., que el traslado del cual fue objeto la accionante en nada afect\u00f3 las condiciones laborales que rodeaban su cargo, pues estas se conservaron, siendo las mismas que pose\u00eda antes del mencionado traslado. \u00a0<\/p>\n<p>En cuanto al riesgo que representa su labor, este es igual en cualquier zona del territorial, y se encuentra ligado m\u00e1s en relaci\u00f3n con su funci\u00f3n de inteligencia que con el aspecto geogr\u00e1fico. Por otra parte, no se puede considerar que su derecho fundamental a la salud, le haya sido conculcado, pues en ning\u00fan momento los servicios m\u00e9dicos por ella requeridos le han sido negados. \u00a0<\/p>\n<p>Respecto a la posibilidad de desplazarse fuera de su \u00e1rea de trabajo, las autorizaciones por ella solicitadas, le fueron concedidas en la medida en que el servicio lo permiti\u00f3, y le fueron negadas cuando las condiciones propias de su trabajo as\u00ed no permitieron. \u00a0<\/p>\n<p>Igualmente es importante mencionar que la demandante tiene una asignaci\u00f3n b\u00e1sica de $ 867.960 pesos, m\u00e1s un treinta por ciento (30%) correspondiente a la prima de riesgo, lo cual da un gran total de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 $ 1.128.348 pesos, equivalente a cuatro punto tres (4.3) salarios m\u00ednimo mensual vigente, \u201ccon el cual muchos colombianos subsisten y mantienen a su familia, sin que este sea factor de desintegraci\u00f3n familiar.\u201d \u00a0<\/p>\n<p>\u201cSe colige de lo anterior que, el DAS al contrario de lo que manifiesta ahora la accionante, provey\u00f3 los medios econ\u00f3micos para que \u00e9sta conviviera con sus hijos en su nuevo lugar de trabajo y si ello no ocurri\u00f3, lo fue por voluntad de la se\u00f1ora M\u00e1rquez Illidge.\u201d \u00a0<\/p>\n<p>Por otra parte, no se encuentra justificaci\u00f3n alguna al hecho de que la actora hubiera dejado transcurrir m\u00e1s de once (11) meses desde su traslado para luego hacer evidente su desacuerdo, y reclamar as\u00ed por v\u00eda de tutela su reubicaci\u00f3n. En este punto recuerda la entidad accionada, que la actora dispon\u00eda de otra v\u00eda judicial por medio de la cual pudo en su momento controvertir la resoluci\u00f3n por la cual se ordenaba su traslado; acto administrativo que pudo ser demandado ante la jurisdicci\u00f3n contencioso administrativa mediante la acci\u00f3n de nulidad y restablecimiento del derecho, acci\u00f3n que pudo ejercer dentro de los cuatro (4) meses siguientes a la notificaci\u00f3n de la resoluci\u00f3n. Por ello, se considera que no es la tutela la v\u00eda judicial apropiada para revivir los t\u00e9rminos de la acci\u00f3n que por negligencia no fue empleada por la tutelante en su momento. \u00a0<\/p>\n<p>As\u00ed mismo, el Director del D.A.S. se\u00f1ala en el mismo escrito, que podr\u00eda concluirse que ha sido la misma actora quien con su conducta ha atentado contra la unidad familiar y los derechos de sus hijos, al no aceptar el traslado de los mismos a su nuevo lugar de trabajo, y al permanecer en la instituci\u00f3n conociendo las condiciones de riesgo de la \u00a0labor por ella desarrollada. \u00a0<\/p>\n<p>Finalmente, considera el ente demandado, que \u201c de las argumentaciones que sobre el particular expone la accionante, es claro que su \u00fanico objetivo con la interposici\u00f3n de la presente tutela es que por este mecanismo judicial, se le destine nuevamente a la Seccional DAS Magdalena, lugar en el cual seg\u00fan ella, s\u00ed existe el clima ideal para su salud y en donde nunca sentir\u00eda estr\u00e9s, etc.; no obstante, es de considerar que aceptar la utilizaci\u00f3n de la tutela con tales prop\u00f3sitos, cuando ni siquiera existe solicitud formal de traslado, es obligar a la administraci\u00f3n a que no pueda disponer del personal que labora en esta Entidad ya que seguramente todos los funcionarios pretender\u00e1n que se les traslade a San Andr\u00e9s, Santa Marta o a Cartagena, sin que se pueda entonces laborar en sitios como Leticia, Quibdo, Florencia, \u2018Villavicencio\u2019 entre otros m\u00e1s.\u201d(negrillas y subraya fuera del texto original). \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. DECISIONES JUDICIALES OBJETO DE REVISI\u00d3N. \u00a0 \u00a0<\/p>\n<p>Impugnada la anterior decisi\u00f3n, conoci\u00f3 la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia, la cual en sentencia del 14 de febrero de 2000, revoc\u00f3 la decisi\u00f3n del a quo. \u00a0Consider\u00f3 el ad quem que \u201c puede afirmarse que son de dos tipos las razones por las cuales se solicita la protecci\u00f3n demandada: unas de orden personal provenientes del estado de salud de la accionante, argumento ligado a la vida digna y al ambiente sano; y otras de \u00edndole familiar que tienden a que se proteja la mujer cabeza de familia, la unidad familiar y el derecho a no ser separada de ella, la ni\u00f1ez, la seguridad, tener un ambiente sano, y en fin, los derechos que hacen referencia a la relaci\u00f3n familiar entre la madre y los hijos, y, en especial, aquellas razones dirigidas a resaltar el impacto socio-sicol\u00f3gico que sufren los miembros de la familia ante una separaci\u00f3n forzada, a la que se ven expuestos tanto la actora como los menores para quienes pide su protecci\u00f3n, por las circunstancias laborales que se describen en la demanda.\u201d \u00a0<\/p>\n<p>En relaci\u00f3n con el primer tipo de razones, el ad quem no encuentra una relaci\u00f3n de causalidad entre la orden de traslado y los padecimientos de salud que sufre la accionante, pues no es claro que la causa de sus dolencias sea precisamente consecuencia de la orden impartida por su empleador. Igualmente, se demostr\u00f3 que en ning\u00fan momento los servicios m\u00e9dicos requeridos le hubieran sido negados. En cuanto a los v\u00ednculos familiares, estos se construyen sobre unas bases s\u00f3lidas conformadas por lazos afectivos que no desaparecen por el desplazamiento de la madre. Dicha uni\u00f3n familiar podr\u00eda conservarse m\u00e1s fuerte en el evento en que la propia madre se re\u00fana con sus hijos y asuma la funci\u00f3n plena como cabeza de familia. La anterior situaci\u00f3n depende es de la propia actora y no es consecuencia del acto administrativo que ella controvierte en esta tutela. Igualmente, sostuvo la Corte Suprema que el tratamiento m\u00e9dico de la actora se puede seguir en cualquier parte del pa\u00eds, salvo la situaci\u00f3n extrema en que s\u00f3lo en un sitio del pa\u00eds encuentre la soluci\u00f3n requerida, circunstancia que en el presente caso no aparece demostrada. Por las anteriores razones, se revoc\u00f3 la decisi\u00f3n de primera instancia. \u00a0<\/p>\n<p>III. CONSIDERACIONES Y FUNDAMENTOS. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Competencia. \u00a0 \u00a0<\/p>\n<p>De conformidad con lo establecido en los art\u00edculos 86 y 241-9 de la Constituci\u00f3n Pol\u00edtica y en los art\u00edculos 31 a 36 del Decreto 2591 de 1991, la Corte Constitucional es competente para revisar las decisiones judiciales mencionadas. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Ius variandi. Limites y alcance de dicho principio. Reiteraci\u00f3n de jurisprudencia. \u00a0 \u00a0<\/p>\n<p>Ha sido muy prol\u00edfica la jurisprudencia emanada de esta Corporaci\u00f3n2 en relaci\u00f3n con el principio del ius variandi, y en particular en lo relativo a sus alcances y limitaciones. \u00a0<\/p>\n<p>En sentencia T-407 de 1992, Magistrado Ponente Sim\u00f3n Rodr\u00edguez Rodr\u00edguez, se se\u00f1al\u00f3 lo siguiente: \u00a0<\/p>\n<p>&#8220;Consiste el jus variandi en la facultad que tiene el patrono de alterar las condiciones de trabajo en cuanto al modo, lugar, cantidad o tiempo de trabajo y ello en virtud del poder subordinante que ejerce sobre sus trabajadores. Su uso estar\u00e1 determinado por las conveniencias razonables y justas que surgen de las necesidades de la empresa y que de todas maneras, seg\u00fan lo tiene establecido la doctrina y la jurisprudencia, habr\u00e1 de preservarse el honor, la dignidad, los intereses, los derechos m\u00ednimos y seguridad del trabajador y dentro de las limitaciones que le imponen la ley, el contrato de trabajo, la convenci\u00f3n colectiva y el reglamento de trabajo. \u00a0<\/p>\n<p>&#8220;&#8230; el empresario ha de guiar sus actuaciones frente al asalariado dentro de las m\u00ednimas condiciones del debido respeto a la dignidad de sus operarias, porque, seg\u00fan se ha explicado precedentemente, es consubstancial tal dignidad \u00a0con \u00a0 la \u00a0 naturaleza \u00a0del \u00a0 hombre-persona y cabalmente, de la relaci\u00f3n que se establece entre obrero y patrono y en raz\u00f3n del poder subordinante del \u00faltimo sobre el primero, pueden aparecer situaciones conflictivas de abuso que el ordenamiento constitucional no tolera, porque se repite ha \u00a0 de \u00a0entenderse \u00a0 \u00a0que \u00a0 \u00a0al \u00a0 empleador \u00a0 se \u00a0 le \u00a0 prohibe categ\u00f3ricamente atentar contra la dignidad de sus empleados.\u201d \u00a0<\/p>\n<p>Igualmente se ha indicado por esta Corte el car\u00e1cter relativo de dicho concepto. Al respecto dijo: \u00a0<\/p>\n<p>&#8220;El jus variandi no es absoluto. Est\u00e1 limitado, ante todo, por la norma constitucional que exige para el trabajo condiciones dignas y justas (art. 25 C.N.), as\u00ed como por los principios m\u00ednimos fundamentales se\u00f1alados por el art\u00edculo 53 de la Carta en lo que concierne al estatuto del trabajo. Y, por supuesto, su ejercicio concreto depende de factores tales como las circunstancias que afectan al trabajador, la situaci\u00f3n de su familia, su propia salud y la de sus allegados, el lugar y el tiempo de trabajo, sus condiciones salariales, la conducta que ha venido observando y el rendimiento demostrado. En cada ejercicio de su facultad de modificaci\u00f3n el empleador deber\u00e1 apreciar el conjunto de estos elementos y adoptar una determinaci\u00f3n que los consulte de manera adecuada y coherente. En \u00faltimas, debe tomar en cuenta que mediante aquella no queda revestido de unas atribuciones omn\u00edmodas que toman al trabajador como simple pieza integrante de la totalidad sino como ser humano libre, responsable y digno en quien debe cristalizarse la administraci\u00f3n de justicia distributiva a cargo del patrono.&#8221; (Corte Constitucional, Sentencia. T-483 de 1993). \u00a0<\/p>\n<p>Dichos criterios relativos a las m\u00ednimas condiciones del debido respeto a la dignidad de los trabajadores, tiene plena aplicaci\u00f3n respecto de \u00a0cualquier empleador, sin importar que \u00e9ste sea sujeto de derecho p\u00fablico o privado.3 \u00a0<\/p>\n<p>Igualmente, la estructura interna que tienen muchas de las entidades del Estado, en raz\u00f3n a los fines que constitucionalmente les ha sido confiados, requieren de una planta de personal de car\u00e1cter global y flexible, que les permita tener la capacidad suficiente para cumplir cabalmente con las funciones a su cargo, pudiendo por lo tanto, \u00a0reubicar o trasladar a sus funcionarios en cualquiera de sus diferentes sedes o dependencias, en el nivel territorial o nacional, decisi\u00f3n que debe ser siempre asumida tanto por el empleador como por el mismo trabajador, como consecuencia de la aplicaci\u00f3n de criterios razonables que s\u00f3lo buscan una mejor prestaci\u00f3n del servicio. \u00a0<\/p>\n<p>El Departamento Administrativo de Seguridad D.A.S., es un ente de car\u00e1cter nacional, cuya labor de investigaci\u00f3n es fundamental para la seguridad nacional en sus diferentes aspectos. Es por ello, que el recurrir al principio del ius variandi, en aras de lograr un mejor nivel en la prestaci\u00f3n de sus servicios, y ello significa, que dicho principio no puede sustentarse en la arbitrariedad sino en la discrecionalidad,4 pues ante todo, deben primar los derechos constitucionales de los trabajadores que se ven involucrados en la decisi\u00f3n asumida por su empleador. \u00a0<\/p>\n<p>En el presente caso, como en muchos otros ya resueltos por esta Corporaci\u00f3n,5 se ha manifestado de manera muy clara que la acci\u00f3n de tutela no es el medio judicial apropiado para controvertir la legalidad del acto administrativo por medio del cual se ordena un traslado ni tampoco para lograr su revocatoria, suspensi\u00f3n o reforma, pues el juez constitucional no tiene dicha competencia y de hacerlo, no s\u00f3lo estar\u00eda desbordando la \u00f3rbita de su competencia, sino tambi\u00e9n invadiendo la de otros jueces, como la del juez contencioso administrativo en el presente caso. \u00a0<\/p>\n<p>De esta forma, la acci\u00f3n de tutela como mecanismo judicial de car\u00e1cter excepcional, no es viable como medio para pretender echar abajo una orden de traslado laboral. Sin embargo, debe recordarse, que en aras de la protecci\u00f3n de los derechos fundamentales, para lo cual la acci\u00f3n de tutela es el medio judicial adecuado, \u00e9sta ser\u00e1 procedente en excepcionales circunstancias f\u00e1cticas en las cuales debe estar presente cuando menos una de varias condiciones, que har\u00eda del traslado una conducta arbitraria por parte de su empleador. Tales condiciones fueron claramente expuestas en la sentencia T-965 de 2000, Magistrado Ponente Eduardo Cifuentes Mu\u00f1oz:\u00a0 \u00a0<\/p>\n<p>\u201c (1) que el traslado tenga como consecuencia necesaria la afectaci\u00f3n de la salud del servidor p\u00fablico o de alguno de los miembros de su n\u00facleo familiar, especialmente porque en la localidad de destino no existan condiciones adecuadas para brindarle el cuidado m\u00e9dico requerido6; (2) cuando la decisi\u00f3n de trasladar al trabajador es intempestiva y arbitraria y tiene como consecuencia necesaria la ruptura del n\u00facleo familiar, siempre que no suponga simplemente una separaci\u00f3n transitoria u originada en factores distintos al traslado o a circunstancias superables7; (3) cuando quede demostrado que el traslado pone en serio peligro la vida o la integridad personal del servidor p\u00fablico o de su familia8. No sobra advertir que, para que la acci\u00f3n de tutela pueda proceder, las circunstancias alegadas deben encontrar pleno respaldo probatorio en el correspondiente expediente9.\u201d \u00a0<\/p>\n<p>En el caso objeto de revisi\u00f3n, encuentra la Sala que respecto de la primera condici\u00f3n esta no se encuentra presente en este proceso, por cuanto los servicios m\u00e9dicos que la accionante ha requerido para tratar sus diferentes dolencias le han sido prestados de manera completa, teniendo en cuenta adem\u00e1s, que los niveles de prestaci\u00f3n en salud requeridos por la accionante le son cubiertos sin ning\u00fan problema en la ciudad de Villavicencio e igualmente en la ciudad de Bogot\u00e1 que dista tan s\u00f3lo de la primera en dos horas de viaje. Adem\u00e1s, en la medida en que su condici\u00f3n de salud tambi\u00e9n depende de los niveles de estr\u00e9s que la accionante maneje, considera la Sala que dada su condici\u00f3n de miembro del cuerpo de inteligencia del D.A.S., los niveles de cansancio, riesgo y presi\u00f3n que su propia labor le generan no variar\u00edan en gran medida s\u00ed sus servicios se prestaran en otra ciudad del pa\u00eds. \u00a0<\/p>\n<p>En cuanto a la afectaci\u00f3n de la unidad familiar, recuerda la Sala, que tal como lo indicara el mismo Director del D.A.S. en escrito remitido al juez de conocimiento, cada funcionario al momento de ser traslado a lugar diferente al de su \u00faltimo domicilio, y que tenga a su cargo, c\u00f3nyuge, padres o hijos, tendr\u00e1 derecho a una prima de instalaci\u00f3n que corresponde a treinta (30) d\u00edas de su salario b\u00e1sico. De esta manera es claro que, la accionante tuvo la oportunidad de conservar consigo a sus hijos, de ubicarlos en la misma ciudad a la que fue trasladada, y de igual manera, reducir los costos que implicaba tenerlos en otra ciudad (ya sea Bogot\u00e1 o Santa Marta), lo que hubiera incidido positivamente, en el mantenimiento de su unidad familiar, en el comportamiento de sus hijos y en su econom\u00eda dom\u00e9stica, que ella misma alega como bastante resquebrajada. Est\u00e1 demostrado, por lo tanto, que el empleador dispuso de todos los medios legalmente establecidos para que los inconvenientes propios del traslado de lugar de trabajo de uno de sus funcionarios, tuviera el menor impacto en su vida personal, fue una oportunidad que la accionante desech\u00f3, y que ahora por este medio reclama. Ello no impide, que pueda actualmente reunirse con sus hijos en su lugar de trabajo. \u00a0<\/p>\n<p>\u00a0 \u00a0<\/p>\n<p>La \u00faltima de las condiciones estipuladas para que se pueda reconsiderar el traslado de un trabajador, es que con dicho traslado se ponga en peligro su vida. En el presente caso, dicha condici\u00f3n no opera en forma plena, pues las caracter\u00edsticas del trabajo desempe\u00f1ado por la accionante \u2013 Auxiliar de Inteligencia 201-13 en el Departamento Administrativo de Seguridad D.A.S., la obligan a desarrollar labores investigativas contra la delincuencia en todas sus modalidades, y ello conlleva un riesgo permanente, que no surge con ocasi\u00f3n de su traslado a una ciudad o poblaci\u00f3n en particular, sino que es de la esencia de la labor misma. Entonces, no es el traslado de la accionante lo que pueda en un momento dado poner en peligro su vida, sino la actividad misma a ella encomendada, situaci\u00f3n que era de amplio conocimiento por la misma actora. \u00a0<\/p>\n<p>Finalmente, encuentra la Sala, que revisado el expediente de tutela, no se encontr\u00f3 petici\u00f3n alguna o prueba que demuestre que efectivamente la accionante hubiera solicitado directamente al D.A.S. su traslado a la ciudad de Santa Marta o en su defecto a Barranquilla, como as\u00ed lo solicita en la demandad de tutela. S\u00f3lo obran constancias de los permisos o autorizaciones por ella solicitados para desplazarse a diferentes ciudades, justificados siempre en motivos personales o familiares, as\u00ed como las contestaciones a los mismos. \u00a0<\/p>\n<p>Encuentra la Sala que no existe vulneraci\u00f3n a los derechos invocados por la accionante. Igualmente, no se encuentran presentes los elementos para que se hable de un verdadero perjuicio irremediable,10 como son la inminencia, la urgencia y la gravedad del peligro. \u00a0<\/p>\n<p>Vistas las anteriores consideraciones, esta Sala de Revisi\u00f3n confirmar\u00e1 la decisi\u00f3n proferida por la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia, con base en las consideraciones aqu\u00ed expuestas. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0<\/p>\n<p>I. DECISI\u00d3N. \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, la Sala Quinta de Revisi\u00f3n de la Corte Constitucional, administrando justicia en nombre del pueblo y por mandato de la Constituci\u00f3n,\u00a0 \u00a0<\/p>\n<p>RESUELVE: \u00a0<\/p>\n<p>Primero. CONFIRMAR la sentencia proferida por la Sala de Casaci\u00f3n Civil de la Corte Suprema de Justicia del 14 de febrero de 2000. \u00a0<\/p>\n<p>Segundo. Por Secretar\u00eda General, l\u00edbrese la comunicaci\u00f3n prevista en el art\u00edculo 36 del decreto 2591 de 1991. \u00a0<\/p>\n<p>Notif\u00edquese, comun\u00edquese, publ\u00edquese en la Gaceta de la Corte Constitucional y c\u00famplase. \u00a0<\/p>\n<p>RODRIGO ESCOBAR GIL \u00a0<\/p>\n<p>Magistrado Ponente \u00a0<\/p>\n<p>MARCO GERARDO MONROY CABRA \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>EDUARDO MONTEALEGRE LYNETT \u00a0<\/p>\n<p>Magistrado \u00a0<\/p>\n<p>MARTHA VICTORIA S\u00c1CHICA DE MONCALEANO \u00a0<\/p>\n<p>Secretaria General \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>1 A Folios 64 y 65 del expediente objeto de revisi\u00f3n, obran fotocopias simples de los Registros de Nacimiento de Mayra Alejandra Palacio M\u00e1rquez (febrero 8 de 1997) y Elkis Alejandro Palacio M\u00e1rquez (Enero 18 de 1993), en los que se demuestra que son hijos de la accionante. \u00a0<\/p>\n<p>2 Para ver una evoluci\u00f3n jurisprudencial sobre el tema del\u00a0 ius variandi, se puede consultar la sentencia T-503 de 1999, M.P. Carlos Gaviria D\u00edaz. \u00a0<\/p>\n<p>3 Ver sentencia T-483 de 1993, M.P. Jos\u00e9 Gregorio Hern\u00e1ndez Galindo. \u00a0<\/p>\n<p>4 \u00a0Ver sentencia C-071 de 1994, M.P. Alejandro Mart\u00ednez Caballero. \u00a0<\/p>\n<p>5 Entre otras sentencias, ver las sentencias T-399 de 1996, M.P. Jorge Arango Mej\u00eda\u00a0; T-715 de 1996, M.P. Eduardo Cifuentes Mu\u00f1oz\u00a0; T-832 de 1998, M.P. Antonio Barrera Carbonell\u00a0; T-503 de 1999, M.P. Carlos Gaviria D\u00edaz\u00a0; T-965 de 2000, M.P. Eduardo Cifuentes Mu\u00f1oz y T-209 de 2001, M.P. Alfredo Beltr\u00e1n Sierra. \u00a0<\/p>\n<p>6 Sentencias, T-330\/93 (MP Alejandro Mart\u00ednez Caballero), (T-483\/93 MP Jos\u00e9 Gregorio Hern\u00e1ndez Galindo), T-131\/95 (MP. Jorge Arango Mej\u00eda), T-181\/96 (MP. Alejandro Mart\u00ednez Caballero), T-514\/96 (MP. Jos\u00e9 Gregorio Hern\u00e1ndez Galindo), T-516\/97 (MP. Hernando Herrera Vergara), T-208\/98 (MP. Fabio Mor\u00f3n D\u00edaz) y T-532\/98 (MP Antonio Barrera Carbonell).\u00a0 \u00a0<\/p>\n<p>7 Sentencia T-503\/99 (MP. Carlos Gaviria D\u00edaz). \u00a0\u00a0 \u00a0<\/p>\n<p>8 Sentencia T-120\/97 (MP Carlos Gaviria D\u00edaz); T-532\/96 (MP Antonio Barrera Carbonell).\u00a0 \u00a0<\/p>\n<p>9 Sentencia T-532\/98 (MP Antonio Barrera Carbonell); T-353\/99 (MP Eduardo Cifuentes Mu\u00f1oz). \u00a0<\/p>\n<p>10 Ver sentencia T-485 de 1994, M.P. Jorge Arango Mej\u00eda. \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Sentencia T-752\/01 \u00a0 IUS VARIANDI-Alcance\/IUS VARIANDI-L\u00edmites \u00a0 ACCION DE TUTELA-No es necesaria para cuestionar el ius variandi \u00a0 TRASLADO DE EMPLEADO DEL DAS-Empleador dispuso los medios necesarios \u00a0 ACCION DE TUTELA-Inexistencia de perjuicio irremediable \u00a0 Reiteraci\u00f3n de Jurisprudencia \u00a0 Referencia: expediente T-440655 \u00a0 Acci\u00f3n de tutela instaurada por Marlene M\u00e1rquez Illidge contra el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-7858","post","type-post","status-publish","format-standard","hentry","category-tutelas-2001"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/7858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/comments?post=7858"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/posts\/7858\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/media?parent=7858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/categories?post=7858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/corteconstitucionalcronologico202454587\/wp-json\/wp\/v2\/tags?post=7858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}