{"id":15749,"date":"2023-07-07T19:42:26","date_gmt":"2023-07-07T19:42:26","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-223-de-1981\/"},"modified":"2023-07-07T19:42:26","modified_gmt":"2023-07-07T19:42:26","slug":"decreto-223-de-1981","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-223-de-1981\/","title":{"rendered":"DECRETO 223 DE 1981"},"content":{"rendered":"\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETO 223 \u00a0DE 1981 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(enero 29 de 1981) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">por el cual se incorpora al ordenamiento jur\u00eddico nacional el reglamento del instrumento \u00a0andino de seguridad social. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Presidente de la Rep\u00fablica de Colombia, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">en uso de sus facultades constitucionales y en desarrollo de la \u00a0 Ley 22 de 1979 por \u00a0medio de la cual el Congreso Nacional imparti\u00f3&#8217; aprobaci\u00f3n al Convenio Sim\u00f3n Rodr\u00edguez, de integraci\u00f3n \u00a0socio-laboral, firmado en Caracas el 26 de octubre de 1973 y el protocolo del \u00a0Convenio Sim\u00f3n Rodr\u00edguez, firmado en la ciudad de Cartagena el 12 de mayo de 1976, y \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CONSIDERANDO \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Que mediante decreto n\u00famero&#8230; fue \u00a0incorporada al ordenamiento \u00a0jur\u00eddico nacional la Decisi\u00f3n \u00a0n\u00famero 113 de la Comisi\u00f3n del Acuerdo de Cartagena, constitutiva del \u00a0&#8220;instrumento andino de seguridad social&#8221;; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Que la Comisi\u00f3n del Acuerdo de Cartagena, durante XXIV per\u00edodo de sesiones extraordinarias celebrado en la ciudad de Bogot\u00e1 del 3 al 7 de \u00a0septiembre de 1979, expidi\u00f3 la Decisi\u00f3n n\u00famero 148 por la cual se establece el \u00a0&#8220;Reglamento del Instrumento Andino de Seguridad Social&#8221;; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Que es competencia \u00a0exclusiva del Gobierno, como encargado de cumplir y hacer cumplir las \u00a0leyes y de dirigir las relaciones diplom\u00e1ticas y comerciales con los dem\u00e1s Estados y entidades de Derecho Internacional, \u00a0expedir los actos internos de incorporaci\u00f3n al ordenamiento jur\u00eddico nacional \u00a0de las normas supranacionales indirectas, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETA \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 1. Incorporase al \u00a0ordenamiento jur\u00eddico nacional el &#8220;Reglamento \u00a0del Instrumento Andino de Seguridad Social&#8221; establecido en la Decisi\u00f3n 148 \u00a0de la Comisi\u00f3n del: Acuerdo de \u00a0Cartagena, cuyo texto es el siguiente: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECISI\u00d3N 148 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Reglamento del Instrumento Andino de Seguridad Social. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO I \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Disposiciones preliminares. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 1. Los t\u00e9rminos definidos en el art\u00edculo 1\u00ba del Instrumento Andino de Seguridad \u00a0Social, aprobado mediante Decisi\u00f3n 113 de la Comisi\u00f3n \u00a0del Acuerdo de Cartagena, ser\u00e1n utilizados en este Reglamento en el \u00a0mismo sentido expresado \u00a0en dichas definiciones. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 2. Al Instrumento Andino de \u00a0Seguridad Social se le sanciona \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0en este \u00a0Reglamento con la expresi\u00f3n \u00a0&#8220;El Instrumento&#8221;. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO II \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0De las oficinas de coordinaci\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 3. Las autoridades \u00a0competentes de cada uno de los Pa\u00edses Miembros designar\u00e1n ante la Secretar\u00eda \u00a0Ejecutiva prevista en el \u00a0art\u00edculo 19 del Instrumento, la oficina que en su respectivo pa\u00eds servir\u00e1 como \u00a0intermediario en los tr\u00e1mites, informaciones, notificaciones y dem\u00e1s actos \u00a0administrativos que requiera la aplicaci\u00f3n del Instrumento y de este Reglamento \u00a0que tendr\u00e1 el nombre de Oficina de Coordinaci\u00f3n. De hacer cambio en la Oficina \u00a0designada, la autoridad competente lo pondr\u00e1 en conocimiento de la Secretar\u00eda \u00a0Ejecutiva. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO III \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Exenciones a la legislaci\u00f3n aplicable. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 4 Los trabajadores que \u00a0fueren destinados por su empleador a trabajar temporalmente en otro Pa\u00eds \u00a0Miembro, se mantendr\u00e1n sometidos a la legislaci\u00f3n del pa\u00eds del cual proceden, \u00a0siempre que la permanencia en el otro no fuere mayor de doce meses. El \u00a0empleador deber\u00e1 entregar a la instituci\u00f3n de estada un certificado de la \u00a0instituci\u00f3n competente acerca de que el trabajador continuar\u00e1 afectado a su \u00a0legislaci\u00f3n. Podr\u00e1 prorrogarse el indicado plazo por dos meses, a petici\u00f3n del \u00a0empleador, presentado ante la instituci\u00f3n competente, la cual deber\u00e1 de \u00a0inmediato obtener la conformidad de la instituci\u00f3n del lugar de estada. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 5. Los trabajadores cuyo \u00a0lugar de trabajo no es fijo y realizaren su labor en forma itinerante entre \u00a0diversos Pa\u00edses Miembros como los mencionados en el art\u00edculo literal b) del Instrumento; estar\u00e1n sometidos a la \u00a0legislaci\u00f3n del Pa\u00eds Miembro en el que la empresa \u00a0empleadora tuviere su domicilio principal. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 6. En el caso de \u00a0trabajadores que ejerzan su actividad en una empresa de explotaci\u00f3n crusado por \u00a0una frontera com\u00fan, se \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0aplicar\u00e1 la legislaci\u00f3n del Pa\u00eds Miembro en el cuaI el \u00a0empleador se halla domiciliado. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO IV \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0De la totalizaci\u00f3n de per\u00edodos.&#8217; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 7. Los per\u00edodos de aportaci\u00f3n y los per\u00edodos asimilados cumplidos simult\u00e1neamente en instituciones de dos o m\u00e1s pa\u00edses Miembros, se \u00a0contar\u00e1n solo una vez \u00a0para la totalizaci\u00f3n \u00a0de per\u00edodos prevista en el art\u00edculo \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a07\u00ba del Instrumento. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 8. En caso de superposci\u00f3n de per\u00edodos acreditados en diversos Pa\u00edses Miembros, al efectuar la totalizaci\u00f3n se aplicar\u00e1n las \u00a0siguientes reglas: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Si coincidieren per\u00edodos de seguro \u00a0obligatorio, se excluir\u00e1 el per\u00edodo acreditado en el pa\u00eds en que el asegurado se hubiere \u00a0inscrito en segundo t\u00e9rmino; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Si coincidiere un per\u00edodo de seguro \u00a0(obligatorio o voluntario), con un per\u00edodo asimilado, se excluir\u00e1 este \u00faltimo; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Si coincidieren per\u00edodos \u00a0asimilados, se tendr\u00e1 en cuenta solamente el cumplido en el Pa\u00eds Miembro en que se acredite el \u00a0per\u00edodo de seguro inmediatamente anterior; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Si coincidiere un per\u00edodo de seguro \u00a0obligatorio con per\u00edodos de seguro voluntario, originales o continuados, se \u00a0excluir\u00e1n estos \u00faltimos, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Si coincidieren dos o m\u00e1s per\u00edodos de seguro voluntario, \u00a0se tendr\u00e1 en cuenta el cumplido en el Pa\u00eds Miembro en que se acredite el \u00a0per\u00edodo de seguro obligatorio inmediatamente anterior. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 9. Al efectuar la \u00a0totalizaci\u00f3n de per\u00edodos y \u00fanicamente para efectos de computo, cada instituci\u00f3n \u00a0competente har\u00e1 la \u00a0conversi\u00f3n de unidades de tiempo, de conformidad con las siguientes reglas: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Seis (6) d\u00edas equivalen a una (1) semana y viceversa; la fracci\u00f3n restante que \u00a0exceda de tres (3) d\u00edas equivale a una (1) semana; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Veintiseis (26) d\u00edas equivalen a un \u00a0(1) mes y viceversa; Ia fracci\u00f3n restante que exceda de trece(13) d\u00edas equivale a un \u00a0(1) mes; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Para la conversi\u00f3n de semanas en meses y viceversa, las semanas y \u00a0los meses se \u00a0convierten en d\u00edas seg\u00fan las equivalencias y anteriores tres \u00a0(3) meses equivalente a trece (13) semanas), y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Tres (3) meses o trece (13) semanas o setenta y ocho \u00a0(78) d\u00edas, equivalente a un trimestre y viceversa; \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0la fracci\u00f3n restante de dos (2) meses, de \u00a0siete (7) semanas o m\u00e1s de treinta y nueve (39) d\u00edas, equivalen a un (1) \u00a0trimestre. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 10. Caso de que el asegurado \u00a0tuviere per\u00edodos de seguro en un r\u00e9gimen especial correspondiente a determinada \u00a0profesi\u00f3n \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0o actividad, en alguno \u00a0de los Pa\u00edses Miembros prevista en su respectiva legislaci\u00f3n, dichos per\u00edodos \u00a0entrar\u00e1n en la totalizaci\u00f3n general, si fueren para la misma rama de seguro. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO V \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Prestaciones de enfermedad y maternidad. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 11. Para beneficiarse de las prestaciones por enfermedad o maternidad, los trabajadores de un Pa\u00eds Miembro que por cualquier causa estuvieren temporalmente en el territorio de otro Pa\u00eds Miembro, deber\u00e1n presentar a la \u00a0instituci\u00f3n de \u00a0estada un certificado conferido por la instituci\u00f3n competente, \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0en el cual conste lo siguiente: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Los datos necesarios de identificaci\u00f3n; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) La vigencia del derecho; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) El tiempo m\u00e1ximo durante el cual se \u00a0conceden las prestaciones; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) El valor del salario base del \u00a0c\u00e1lculo, y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Los casos en que las prestaciones se suspenden. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Igual certificado deber\u00e1n presentar los miembros de familia de los trabajadores que se \u00a0hallaren en el caso del art\u00edculo 8\u00ba del Instrumento, excepci\u00f3n hecha \u00a0 \u00a0 \u00a0 \u00a0 \u00a0de lo indicado en el literal d) de este art\u00edculo. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 12. \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0El trabajador \u00a0 \u00a0 \u00a0 \u00a0 \u00a0que habiendo cesado en el r\u00e9gimen de \u00a0seguridad social de un Pa\u00eds Miembro ingresare al de otro Pa\u00eds Miembro y \u00a0requiriese, para tener derecho alas prestaciones de enfermedad o maternidad, de la \u00a0totalizaci\u00f3n de los per\u00edodos de seguro o asimilados, deber\u00e1 presentar a la \u00a0instituci\u00f3n competente un certificado de la instituci\u00f3n de anterior afiliaci\u00f3n \u00a0que acredite los per\u00edodos de aportaci\u00f3n o asimilados que tuviere registrados en \u00a0esa rama de seguro. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 13. El valor de las \u00a0prestaciones en especie y en servicio se establecer\u00e1 sobre la base del costo \u00a0medio unitario de cada acto m\u00e9dico, servicio o prestaci\u00f3n en la instituci\u00f3n que \u00a0los hubiere suministrado, correspondiente al a\u00f1o inmediato anterior a aquel que \u00a0ese hubieren otorgado dichas prestaciones. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 14. Las instituciones de los Pa\u00edses \u00a0Miembros podr\u00e1n acordar entre s\u00ed procedimientos especiales para estimar el \u00a0costo de las prestaciones en especie y en servicios, en cuyo caso \u00a0prevalecer\u00e1n dichos acuerdos. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 15. Si la instituci\u00f3n competente estima que el \u00a0valor calculado para las prestaciones en \u00a0especie y en servicios es excesivo, tendr\u00e1 derecho a pedir que el Comit\u00e9 \u00a0Administrador proceda a una revisi\u00f3n del c\u00e1lculo. La decisi\u00f3n de este ser\u00e1 \u00a0definitiva. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 16. El suministro de \u00a0pr\u00f3tesis, grandes aparatos y otras prestaciones en especie de gran complejidad \u00a0e importancia, as\u00ed como de tratamientos de readaptaci\u00f3n funcional o reeducaci\u00f3n \u00a0profesional, estar\u00e1n subordinados a la autorizaci\u00f3n previa de la instituci\u00f3n \u00a0competente, salvo casos de urgencia en que las prestaciones no puedan ser \u00a0diferidas sin comprometer gravemente la salud del interesado. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Comit\u00e9 Administrador determinar\u00e1 y \u00a0actualizar\u00e1 peri\u00f3dicamente, con car\u00e1cter obligatorio, las pr\u00f3tesis, grandes aparatos \u00a0y prestaciones en especie que deber\u00e1 quedar Comprendidos en esta disposici\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 17. Las prestaciones en \u00a0dinero ser\u00e1n concedidas por la instituci\u00f3n de residencia o estada, teniendo en \u00a0cuenta el salario que conste en el certificado a que se refiere el art\u00edculo 11, \u00a0en su propia moneda nacional, efectuando la conversi\u00f3n a base de la tasa \u00a0oficial de cambio vigente a la fecha en que se efect\u00fae el pago. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 18. Si el asegurado regresare \u00a0a su pa\u00eds antes de haber percibido la prestaci\u00f3n en dinero a que se refiere el \u00a0art\u00edculo anterior, \u00e9sta le ser\u00e1 concedida y directamente pagada por la \u00a0instituci\u00f3n competente, a cuyo efecto la instituci\u00f3n de estada certificar\u00e1 el \u00a0tiempo de incapacidad que hubiere sufrido el asegurado. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 19. Si la legislaci\u00f3n a que \u00a0se sujete la instituci\u00f3n competente permite una pr\u00f3rroga del per\u00edodo de goce de \u00a0las prestaciones en especie y servicios y en dinero, \u00a0dicha pr\u00f3rroga se har\u00e1 efectiva previa autorizaci\u00f3n de dicha instituci\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 20. Trat\u00e1ndose de pensionistas \u00a0por invalidez y vejez y de beneficiarios de \u00a0pensiones de sobrevivientes, cuyos derechos a \u00a0las respectivas pensiones hayan sido adquiridos en virtud de la totalizaci\u00f3n de per\u00edodos, seg\u00fan lo prescrito \u00a0en el Instrumento, la instituci\u00f3n competente ser\u00e1 la del lugar de su residencia, Si la tuviere \u00a0en uno de los \u00a0Pa\u00edses Miembros que concurrieron a la totalizaci\u00f3n y siempre que la legislaci\u00f3n de este \u00a0reconociere derecho \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0a prestaciones de \u00a0enfermedad y maternidad a dichos \u00a0pensionistas y beneficiarios. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO VI \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Accidentes del trabajo y enfermedades profesionales. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 21. Las disposiciones del \u00a0Cap\u00edtulo anterior sobre prestaciones \u00a0en especie y en servicios y sobre las prestaciones en dinero, se observar\u00e1n respecto de accidentes del \u00a0trabajo y enfermedades profesionales previstas en el art\u00edculo 12 del \u00a0Instrumento, en los casos en, que fueren aplicables. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 22. La instituci\u00f3n competente \u00a0no quedar\u00e1 exenta de la obligaci\u00f3n de reembolso del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0costo de las prestaciones suministradas por la instituci\u00f3n \u00a0de residencia o estada, por el hecho de quo \u00a0este costa debiere ser cargado a la \u00a0responsabilidad del empleador en virtud de disposiciones de la legislaci\u00f3n que \u00a0aplique dicha instituci\u00f3n competente. En tal caso, una vez efectuado el \u00a0reembolso, esto har\u00e1 efectivo la responsabilidad \u00a0del empleador subrogante en la forma legal que corresponda. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">En el caso de asegurador subrogante, \u00a0la instituci\u00f3n del Pa\u00eds Miembro en que este resida, prestar\u00e1 sus buenos oficios a la del \u00a0otro Pa\u00eds Miembros que hubiere suministrado las prestaciones, para hacer efectiva la responsabilidad de \u00a0dicho asegurador. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 23. Cuando para efectos de \u00a0establecer el grado de incapacidad resultante, haya de considerarse la \u00a0preexistencia de un siniestro anterior ocurrido en otro de los Pa\u00edses Miembros, la cuant\u00eda total de la prestaci\u00f3n, \u00a0fijada sobre el \u00faltimo \u00a0salario, ser\u00e1 cubierta por los dos Pa\u00edses Miembros a prorrata del grado de \u00a0disminuci\u00f3n de capacidad que hubiere producido cada siniestro y de conformidad \u00a0con sus respectivas legislaciones. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 24. Toda causa sobreviviente \u00a0que agrave la incapacidad resultante de un siniestro, ser\u00e1 tomada en cuenta asumida \u00a0por la instituci\u00f3n competente, a menos que esa causa sobreviviente \u00a0originase por si \u00a0misma derecho a, prestaciones en el Pa\u00eds Miembro en que se hubiere producido. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO VII \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0De las prestaciones \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0vejez, invalidez y muerte. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Articulo 25. Las solicitudes para \u00a0obtener las prestaciones de vejez e invalidez con la \u00a0totalizaci\u00f3n de per\u00edodos de seguro en dos o m\u00e1s Pa\u00edses Miembros deber\u00e1n presentarse ante fa instituci\u00f3n competente del Pa\u00eds \u00a0Miembro en cuyo territorio el asegurado hubiere, tenido su \u00faltima afiliaci\u00f3n \u00a0del Pa\u00eds Miembros en \u00a0que el asegurado estuviera residiendo. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">En cualquiera de los \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0dos casos, dicha \u00a0instituci\u00f3n se denominar\u00e1 &#8220;Instituci\u00f3n de Tr\u00e1mite&#8221;. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">En cuanto a las prestaciones de \u00a0sobrevivientes; la &#8220;Instituci\u00f3n de Tr\u00e1mite&#8221; ser\u00e1 la de ultima afiliaci\u00f3n del \u00a0asegurado, pero si los deudos residieren en otro u otros de los Pa\u00edses Miembros podr\u00e1n enviar la solicitud a la Instituci\u00f3n de Tr\u00e1mite por intermedio de la \u00a0instituci\u00f3n de seguridad social del pa\u00eds en que residieren y la presentaci\u00f3n en esta \u00a0surtir\u00e1 efectos determinados en el art\u00edculo \u00a028, en lo que respecta a Ia fecha. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 26. La solicitud se presentar\u00e1 en el formulario destinado al efecto, el cual contendr\u00e1 como datos m\u00ednimos, la identificaci\u00f3n del asegurado y de las instituciones de los Pa\u00edses Miembros en los cuales \u00a0este hubiere acreditado \u00a0per\u00edodos asimilados, con indicaci\u00f3n de las fechas entre las cuales se hubieren producido. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Al formulario deber\u00e1 acompa\u00f1ares los \u00a0documentos justificativos del derecho que para cada una de las prestaciones se determinen en \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0el mismo. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a027. La Instituci\u00f3n de Tr\u00e1mite remitir\u00e1 a coda uno de los que hubieren de intervenir en la \u00a0totalizaci\u00f3n, por intermedio de la respectiva, oficina de coordinaci\u00f3n, un \u00a0ejemplar de la solicitud, dentro de los treinta d\u00edas siguientes a su recepci\u00f3n. \u00a0De tratarse de prestaciones de invalidez, remitir\u00e1, junto con el ejemplar de la \u00a0solicitud, un dictamen de m\u00e9dico autorizado por la Instituci\u00f3n de Tr\u00e1mite sobre \u00a0las causas, grado y estimaci\u00f3n de las posibilidades de recuperaci\u00f3n del estado \u00a0de incapacidad del interesado. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 28. La fecha de presentaci\u00f3n \u00a0de la solicitud en Ia Instituci\u00f3n de Tr\u00e1mite se considerar\u00e1 como la fecha de \u00a0presentaci\u00f3n a las dem\u00e1s instituciones y el env\u00edo a estas de los ejemplares de \u00a0la solicitud, suplir\u00e1 la remisi\u00f3n de los documentos justificativos a que se refiere \u00a0 \u00a0 \u00a0 \u00a0 \u00a0el art\u00edculo 26 de este reglamento. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 29. A m\u00e1s tardar dentro de \u00a0los sesenta d\u00edas de recibido el correspondiente ejemplar de la solicitud, las \u00a0instituciones de los Pa\u00edses Miembros que concurrieren a la totalizaci\u00f3n, \u00a0intercambiar\u00e1n entre si, por intermedio de las respectivas oficinas de coordinaci\u00f3n y en el formulario \u00a0destinado al efecto, la informaci\u00f3n relativa a \u00a0los per\u00edodos de seguro, per\u00edodos asimilados y per\u00edodos de seguro voluntario que \u00a0tuviere acreditados el asegurado en la respectiva instituci\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 30. Recibidas las informaciones \u00a0a que se refiere el art\u00edculo anterior, cada una de las instituciones proceder\u00e1 \u00a0al c\u00e1lculo determinado en el art\u00edculo 14 del Instrumento y dictar\u00e1 la \u00a0resoluci\u00f3n correspondiente, copia de la cual se remitir\u00e1 a la Instituci\u00f3n de \u00a0Tr\u00e1mite para su notificaci\u00f3n a los interesados. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">En la propia resoluci\u00f3n se fijar\u00e1 el \u00a0importe de la pensi\u00f3n parcial que corresponda conceder a la respectiva \u00a0instituci\u00f3n caso de haber lugar al derecho seg\u00fan su legislaci\u00f3n; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">De tratarse de pensiones de \u00a0 \u00a0 \u00a0 \u00a0 \u00a0sobrevivientes, la resoluci\u00f3n contendr\u00e1 el nombre y la \u00a0cuota de cada uno de ellos. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 31. La Instituci\u00f3n de Tr\u00e1mite \u00a0comunicar\u00e1 a las dem\u00e1s la fecha en que se hizo la notificaci\u00f3n a los \u00a0interesados ya partir de \u00a0esta se contar\u00e1n los plazos para la interposici\u00f3n de los recursos que establezca coda una de las \u00a0legislaciones de los pa\u00edses \u00a0que concurren al otorgamiento \u00a0de las pensiones, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 32. En caso de disconformidad con la decisi\u00f3n adoptada por alguna de las \u00a0instituciones; los interesados \u00a0podr\u00e1n presentar sus recursos ante la Instituci\u00f3n de Tr\u00e1mite, la cual los enviar\u00e1 con la respectiva \u00a0fe de presentaci\u00f3n a \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0la instituci\u00f3n que hubiere&#8221; dictado la \u00a0resoluci\u00f3n recurrida, sin perjuicio de \u00a0que los interesados puedan interponer \u00a0sus recursos directamente ante la autoridad administrativa o judicial que \u00a0proceda. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 33. La interposici\u00f3n de un \u00a0recurso de la resoluci\u00f3n de cualquiera de los pa\u00edses concurrentes a la \u00a0totalizaci\u00f3n, dejar\u00e1 en \u00a0suspenso la ejecuci\u00f3n de las dem\u00e1s, hasta cuando dicho recurso fuere resuelto \u00a0de manera definitiva, a menos que los interesados optaren por una de las alternativas se\u00f1aladas \u00a0en \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0el art\u00edculo 37, literales b) y c). \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 34. Las instituciones de cada Pa\u00eds Miembro \u00a0aplicar\u00e1n \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0las normas de su \u00a0respectiva legislaci\u00f3n, para determinar el salario sobre el cual deban calcular la parte de \u00a0la pensi\u00f3n que les corresponde, en virtud de la totalizaci\u00f3n de per\u00edodos se\u00f1alado en el art\u00edculo 7\u00ba del Instrumento. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 35. A la parte de la pensi\u00f3n que \u00a0resultare seg\u00fan el art\u00edculo anterior se aumentaran los \u00a0suplementos que seg\u00fan la misma legislaci\u00f3n se concedan por miembros de familia \u00a0a cargo del asegurado o cualquier otro acrecimiento de la pensi\u00f3n, en \u00a0proporci\u00f3n \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0al importe de dicha \u00a0parte de la pensi\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 36. Los sobrevivientes de un \u00a0asegurado cuyo derecho proviniere de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0la totalizaci\u00f3n de los tiempos de seguro, percibir\u00e1n, \u00a0adem\u00e1s de la parte de la pensi\u00f3n que \u00a0resultare a cargo de cada uno de los Pa\u00edses Miembros que hubieren intervenido \u00a0en la totalizaci\u00f3n, todos las dem\u00e1s prestaciones complementarias que les reconociere la respectiva legislaci\u00f3n por causa de la muerte del causante, siempre que \u00a0cumplieren los requisitos exigidos por la misma. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 37. Cuando el derecho a las pensiones no hubiere sido alcanzado \u00a0simult\u00e1neamente, seg\u00fan lo dispuesto en el art\u00edculo 14 del Instrumento, los interesados podr\u00e1n optar por \u00a0cualquiera de las siguientes posibilidades: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Postergar el derecho a la pensi\u00f3n \u00a0total hasta cuando se cumplan los requisitos del caso en el pa\u00eds o pa\u00edses donde \u00a0no pudieron obtenerlo; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Acogerse \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0al goce de las pensiones parciales de los Pa\u00edses \u00a0Miembros en que si les es posible obtener el derecho, a pesar de la exclusi\u00f3n \u00a0del pa\u00eds en que este no pudo ser alcanzada, sin perjuicio de pedir \u00a0una nueva totalizaci\u00f3n cuando en el futuro llegaren a cumplir las condiciones \u00a0exigidas por la instituci\u00f3n o instituciones de este \u00faltimo pa\u00eds, \u00a0y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Recibir las prestaciones \u00a0sustitutivas que reconocieren las respectivas \u00a0legislaciones a favor de \u00a0quienes no alcanzaren el derecho a las prestaciones de \u00a0que se trate, por deficiencia de requisitos. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">En cualquiera de los casos anteriores, \u00a0la opci\u00f3n se \u00a0expresar\u00e1 ante la Instituci\u00f3n \u00a0de tr\u00e1mite y ser\u00e1 irrevocable. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 38. Los m\u00e1ximos y m\u00ednimos de pensiones \u00a0fijados en las legislaciones de los distintos Pa\u00edses Miembros que concurren a \u00a0la totalizaci\u00f3n; ser\u00e1n aplicados por cada uno de \u00e9stos a la fracci\u00f3n que le corresponde \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0en la pensi\u00f3n total, a cuyo efecto se tendr\u00e1 en cuenta \u00a0la parte proporcional de dichos m\u00e1ximos y m\u00ednimos, en la misma relaci\u00f3n que hubiere entre dicha fracci\u00f3n y la \u00a0pensi\u00f3n total. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 39. Cuando en alguno de los \u00a0pa\u00edses que haya concurrido a la totalizaci\u00f3n para el otorgamiento de una \u00a0pensi\u00f3n se decretare una revalorizaci\u00f3n de pensiones, se observar\u00e1n las reglas \u00a0siguientes: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Si la revalorizaci\u00f3n fuere en un \u00a0porcentaje, este se aplicar\u00e1 a la pensi\u00f3n parcial que corresponda al pa\u00eds de \u00a0que se trate, y \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Si la revalorizaci\u00f3n fuere en una \u00a0cantidad fija, el aumento se determinar\u00e1 mediante un prorrateo igual al \u00a0utilizado en el c\u00e1lculo de la pensi\u00f3n inicial, en relaci\u00f3n al per\u00edodo cumplido \u00a0en la instituci\u00f3n que concediere la revalorizaci\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 40. Si en cualquiera de los \u00a0Pa\u00edses Miembros participantes en la totalizaci\u00f3n, el beneficiario o beneficiarios de \u00a0las pensiones estuvieren percibiendo o llegaren a percibir una remuneraci\u00f3n \u00a0estable y peri\u00f3dica par el trabajo o a gozar de otras prestaciones en dinero de \u00a0la seguridad social, el Pa\u00eds Miembro en que se efect\u00fae tal percepci\u00f3n, \u00a0notificar\u00e1 a los dem\u00e1s dicha circunstancia y cada uno aplicar\u00e1 al caso las \u00a0normas nacionales que rijan en cuanto incompatibilidad, suspensi\u00f3n o reducci\u00f3n \u00a0de la pensi\u00f3n, respecto de la parte debida por cada Pa\u00eds Miembro. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO VIII \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Subrogaci\u00f3n de derechos. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 41. Si alguna de las \u00a0instituciones competentes que conceden una de las prestaciones previstas en el \u00a0Instrumento estuviere en el caso de obtener de un tercero responsable el \u00a0reembolso del costo de dicha prestaci\u00f3n o del valor efectivo de las mismas, podr\u00e1 efectuar el respectivo reclamo \u00a0y cobro contra el tercero responsable, mediante los buenos oficios de la \u00a0instituci\u00f3n del pa\u00eds donde dicha responsabilidad sea exigible, a cuyo efecto \u00a0proveer\u00e1 a esta \u00faltima instituci\u00f3n de los documentos y poderes que fueren \u00a0necesarios de acuerdo a la Legislaci\u00f3n vigente en el Pa\u00eds Miembros a que esta \u00a0pertenezca: Los gastos que ocasionen las gestiones ser\u00e1n de cuenta de la \u00a0instituci\u00f3n competente. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 42. En el caso de que las instituciones \u00a0que hubieren concurrido a la totalizaci\u00f3n de per\u00edodos de seguro para el \u00a0otorgamiento de una pensi\u00f3n, hubieren de recuperar alguna suma por efecto de la \u00a0responsabilidad de un tercero, su valor se \u00a0distribuir\u00e1 entre las mencionadas instituciones, a pr\u00f3rrata de la parte que a \u00a0cada una corresponda en el pago de la pensi\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO IX. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Pago de prestaciones, reembolsos y transferencias \u00a0monetarias. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 43. El pago de pensiones \u00a0peri\u00f3dicas obtenidas en virtud de la totalizaci\u00f3n de per\u00edodos previsto en el \u00a0Instrumento ser\u00e1 efectuado por parte de la instituci\u00f3n del Pa\u00eds Miembro en que el trabajador o sus deudos \u00a0estuvieren domiciliados. Los cr\u00e9ditos que dicha instituci\u00f3n tuviere \u00a0contra los dem\u00e1s que \u00a0concurren al pago de dichas pensiones se liquidar\u00e1n y compensar\u00e1n anualmente entre cada una de \u00a0ellas y los saldos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0a favor ser\u00e1n pagados de inmediato a la instituci\u00f3n \u00a0que resultare acreedora. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 44. Las remesas se har\u00e1n en \u00a0la moneda oficial del Pa\u00eds Miembro al que pertenezca \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0la instituci\u00f3n acreedora o en alguna divisa de convertibilidad general en los \u00a0Pa\u00edses Miembros, si as\u00ed lo \u00a0permite la respectiva legislaci\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 45. El valor de las \u00a0prestaciones en dinero por enfermedad, maternidad y riesgos del trabajo ser\u00e1 \u00a0reembolsado por la instituci\u00f3n competente a la instituci\u00f3n que las hubiere suministrado, por su \u00a0valor efectivo, dentro de los treinta d\u00edas de recibida la planilla que esta \u00a0\u00faltima deber\u00e1 presentar a la primera. El valor de las prestaciones en especie y en servicio; ser\u00e1 liquidado anualmente \u00a0sobre la base de las planillas que en cada caso deber\u00e1n ser presentados a las \u00a0 \u00a0 \u00a0 \u00a0 \u00a0instituciones competentes por las que hubieren suministrado dichas prestaciones. \u00a0La diferencia que resultare a favor de alguna de las dos instituciones por sus \u00a0cuentas rec\u00edprocas dentro de un ejercicio anual, ser\u00e1 pagado a \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0la instituci\u00f3n \u00a0acreedora al finalizar dicho ejercicio. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">En uno y otro caso los reembolsos se \u00a0har\u00e1n en la moneda a de la instituci\u00f3n acreedora. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 46. Las instituciones de los Pa\u00edses Miembros podr\u00e1n acordar entre s\u00ed otras modalidades de reembolso; en \u00a0especial mediante sistemas de compensaci\u00f3n peri\u00f3dica, en cuyo caso dichos acuerdos \u00a0prevalecer\u00e1n sobre lo dispuesto en e el art\u00edculo anterior. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO X \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0De la Secretaria Ejecutiva Permanente. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 47. La Secretar\u00eda Ejecutiva \u00a0Permanente es el \u00f3rgano \u00a0ejecutivo del Comit\u00e9 Administrador y estar\u00e1 a cargo del Secretario Ejecutivo de \u00a0la Comisi\u00f3n Andina de Seguridad Social. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La Secretar\u00eda Ejecutiva se financiar\u00e1 \u00a0de conformidad con el acuerdo que al respecto adopte la Conferencia de \u00a0Ministros de Trabajo del Grupo Andino. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 48. La sede de la Secretar\u00eda \u00a0Ejecutiva es la ciudad de Lima. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 49. Las funciones de la \u00a0Secretar\u00eda Ejecutiva son las fijadas en el reglamento interno del Comit\u00e9 Administrador \u00a0y las dem\u00e1s se\u00f1aladas en el presente reglamento. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 50. El Secretario Ejecutivo \u00a0tendr\u00e1 la facultad de contratar el personal t\u00e9cnico y administrativo que fuere \u00a0necesario. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 51. El Secretario Ejecutivo \u00a0deber\u00e1 presentar un informe de labores y del estado econ\u00f3mico de la oficina a su cargo, al Comit\u00e9 \u00a0Administrador en la reuni\u00f3n \u00a0ordinaria de este organismo del mes de diciembre de cada a\u00f1o. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO XI \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Disposiciones generales. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Articulo 52. Los buenos oficios que se \u00a0presten entre si las instituciones de los Pa\u00edses Miembros, seg\u00fan lo preceptuado en el art\u00edculo 22 \u00a0del Instrumento, ser\u00e1n gratuitos. Habr\u00e1, lugar \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0al reembolso cuando la instituci\u00f3n que preste sus \u00a0buenos oficios haya tenido que efectuar pagos a terceros en raz\u00f3n de los mismo. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 53. Si en la ejecuci\u00f3n para \u00a0el cobro de cotizaciones a que se refiere el art\u00edculo 25 del Instrumento se \u00a0ocasionaren gastos, estos ser\u00e1n \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0de cuenta de la \u00a0instituci\u00f3n a cuyo favor se hubiera \u00a0ejercitado el procedimiento de cobro y ser\u00e1n pagados mediante deducci\u00f3n de la \u00a0cantidad recaudada, seg\u00fan liquidaci\u00f3n documentada que presentar\u00e1 la instituci\u00f3n \u00a0que hubiere propuesto la ejecuci\u00f3n. De no haber recaudaci\u00f3n o si esta se \u00a0retardare por m\u00e1s de seis meses, esta \u00faltima instituci\u00f3n remitir\u00e1 la liquidaci\u00f3n \u00a0de los gastos efectuados hasta el momento, lo mismo que ser\u00e1 atendido por la \u00a0otra instituci\u00f3n dentro de los treinta d\u00edas subsiguientes al recibo de la \u00a0mencionada liquidaci\u00f3n. Estos pagos se har\u00e1n en la forma prevista en el \u00a0art\u00edculo 44. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 54. La exenci\u00f3n de los \u00a0tr\u00e1mites de legalizaci\u00f3n de los documentos necesarios para la aplicaci\u00f3n del \u00a0convenio se aplicar\u00e1 exclusivamente a los originados oficialmente en las \u00a0instituciones de seguridad social en los Pa\u00edses Miembros y a los que fueren \u00a0presentados por los interesados ante una de esas instituciones, siempre que en \u00a0otro caso sean enviados en la correspondencia oficial de la instituci\u00f3n \u00a0remitente de los documentos. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 55. Los acuerdo que \u00a0celebraren entre s\u00ed los Pa\u00edses Miembros para la mejor aplicaci\u00f3n del \u00a0Instrumento, se deber\u00e1 poner en conocimiento del Comit\u00e9 Administrador dentro de \u00a0los treinta d\u00edas subsiguientes a la fecha en que entren en vigencia en todos \u00a0Ion Pa\u00edses Miembros que los hubieren suscrito. Para el efecto estos enviar\u00e1n un \u00a0ejemplar aut\u00e9ntico de dichos acuerdos a la Secretar\u00eda Ejecutiva. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Disposici\u00f3n transitar\u00eda. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 56. El Comit\u00e9 Administrador \u00a0establecer\u00e1 un sistema para la determinaci\u00f3n en la Subregi\u00f3n de los costos m\u00e9dicos \u00a0unitarios de los actos indicados en el art\u00edculo 13 de este reglamentos. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 2.\u00a0 El presente Decreto \u00a0rige a la fecha de su expedici\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Publ\u00edquese y C\u00famplase. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Dado en Bogot\u00e1, D. E., a 29 de enero \u00a0de 1981. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">JULIO CESAR TURBAY AYALA \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Relaciones Exteriores, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Diego Uribe Vargas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Trabajo y Seguridad \u00a0Social, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Laura Ochoa de Ardila.<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-15749","post","type-post","status-publish","format-standard","hentry","category-decretos-1981"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/15749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=15749"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/15749\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=15749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=15749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=15749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}