{"id":15794,"date":"2023-07-07T19:42:28","date_gmt":"2023-07-07T19:42:28","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-259-de-1981\/"},"modified":"2023-07-07T19:42:28","modified_gmt":"2023-07-07T19:42:28","slug":"decreto-259-de-1981","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-259-de-1981\/","title":{"rendered":"DECRETO 259 DE 1981"},"content":{"rendered":"\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETO 259 DE 1981 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(febrero 6 de 1981) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">por el cual se reglamenta parcialmente el Decreto \u00a0Extraordinario 2277 de 1979, en lo relacionado con inscripci\u00f3n y ascenso en \u00a0el Escalaf\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Modificado por el \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 897 de 1981. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Derogado parcialmente por el \u00a0 Decreto 385 de 1998 \u00a0y por el \u00a0 Decreto 709 de 1996. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Modificado por el \u00a0 Decreto 217 de 2000, \u00a0por el \u00a0 Decreto 1059 de 1989, \u00a0por el Decreto 2480 de 1986 \u00a0y por el \u00a0 Decreto 2669 de 1981. \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">EL Designado Encargado de la Presidencia de la Rep\u00fablica \u00a0de Colombia, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">en ejercicio de las atribuciones que le confieren los numerales 3 \u00a0y 12 del art\u00edculo 120 de la \u00a0 Constituci\u00f3n Pol\u00edtica, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETA \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO I \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Ingreso \u00a0al Escalaf\u00f3n \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 1. \u00a0Condiciones \u00a0para ingreso al Escalaf\u00f3n Nacional Docente. De conformidad con el art\u00edculo 10 del Decreto \u00a0Extraordinario 2277 de 1979, tienen derecho a inscribirse en el Escalaf\u00f3n \u00a0Nacional Docente los educadores titulados en planteles oficiales y no oficiales \u00a0aprobados por el Ministerio de Educaci\u00f3n Nacional. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Su ingreso al Escalaf\u00f3n se realizar\u00e1 al grado que se \u00a0indica en el mismo art\u00edculo en concordancia con la nomenclatura establecida en \u00a0el Decreto 80 de 1980 \u00a0para t\u00edtulos de nivel superior, tal como a continuaci\u00f3n se se\u00f1ala: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Al grado I: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El bachiller pedag\u00f3gico y quienes hayan adquirido un \u00a0t\u00edtulo equivalente antes de la expedici\u00f3n del Decreto \u00a0Extraordinario 2277 de 1979. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Al grado 2: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Perito y el Experto en Educaci\u00f3n, se\u00f1alados en el \u00a0literal a) del Par\u00e1grafo 1\u00ba del Art\u00edculo 1\u00ba del Decreto 2277 de 1979 \u00a0que hayan obtenido el t\u00edtulo antes de la vigencia del citado decreto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Al grado 4: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El T\u00e9cnico Profesional Intermedio en Educaci\u00f3n de que \u00a0trata el inciso final del Art\u00edculo 2\u00ba del Decreto \u00a0extraordinario 80 de 1980. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El T\u00e9cnico o Experto en Educaci\u00f3n se\u00f1alado en el inciso b) \u00a0del par\u00e1grafo 1\u00ba del art\u00edculo 10 del decreto \u00a0extraordinario 2277 de 1979, con titulo otorgado con anterioridad a la \u00a0vigencia del Decreto antes mencionado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Al grado 5: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Tecnol\u00f3gico en Educaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Al grado 6 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) El profesional Universitario con t\u00edtulo diferente al de \u00a0Licenciado en Ciencias de la Educaci\u00f3n, una vez haya aprobado el curso de \u00a0ingreso. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">f) Al grado 7. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Los Licenciados en Ciencias de la Educaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Los Tecn\u00f3logos especializados en Educaci\u00f3n de que trata el \u00a0inciso 30 del art\u00edculo 28 del Decreto \u00a0Extraordinario 80 de 1980. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Para efectos de definici\u00f3n y equivalencia de \u00a0los anteriores t\u00edtulos, se tendr\u00e1 en cuenta lo dispuesto en el par\u00e1grafo 1 del \u00a0Art\u00edculo 10 del Decreto 2277 de 1979 \u00a0y en las disposiciones pertinentes del Decreto 80 de l980. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Los Profesionales Universitarios que adem\u00e1s de su t\u00edtulo \u00a0acrediten uno de los indicados en los literales a), b), c) y d) de este \u00a0art\u00edculo, ser\u00e1n eximidos del curso de ingreso. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 2. \u00a0Procedimiento \u00a0para ingreso. El educador no escalafonado que de conformidad con el Decreto 2277 de 1979 \u00a0tenga derecho a inscribirse en el Escalaf\u00f3n Nacional Docente, deber\u00e1 presentar \u00a0a la Oficina Seccional de Escalaf\u00f3n los siguientes documentos: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Formulario oficial o solicitud de inscripci\u00f3n \u00a0debidamente diligenciado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Certificado de registro civil de nacimiento o partida de \u00a0bautismo si es nacido antes de 1938. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) La copia aut\u00e9ntica del acta de graduaci\u00f3n o la \u00a0constancia de registro del t\u00edtulo certificada por la respectiva Secretar\u00eda de \u00a0Educaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Certificado del curso de capacitaci\u00f3n cuando sea \u00a0requerido para el ingreso, debidamente refrendado por la Direcci\u00f3n General de \u00a0Capacitaci\u00f3n o del Centro Experimental Piloto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Las solicitudes de inscripci\u00f3n al Escalaf\u00f3n \u00a0Nacional Docente, ser\u00e1n resueltas por las juntas dentro de los sesenta (60) \u00a0d\u00edas siguientes al recibo de la respectiva documentaci\u00f3n, siempre y cuando \u00a0llene todos los requisitos exigidos en este Art\u00edculo. La inscripci\u00f3n al \u00a0Escalaf\u00f3n Nacional Docente, surte efectos fiscales para los educadores que se \u00a0encuentren vinculados a la docencia, a partir de la fecha de la resoluci\u00f3n que \u00a0la ordena, y en todo caso, a partir del vencimiento del plazo de los sesenta \u00a0(60) d\u00edas, al recibo de la documentaci\u00f3n completa en los t\u00e9rminos del art\u00edculo \u00a021 del Decreto 2277 de 1979. \u00a0El tiempo de servicio para el ascenso se contar\u00e1 a partir de la fecha en que el \u00a0educador comience a laborar. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Inciso adicionado por el \u00a0 \u00a0 \u00a0 Decreto 897 de 1981* El educador con \u00a0titulo docente que sea nombrado legal y \u00a0reglamentariamente por autoridad nominadora competente, gozara de los \u00a0derechos y garant\u00edas de la carrera docente mientras obtiene su inscripci\u00f3n en \u00a0el Escalaf\u00f3n, siempre que presente los documentos necesarios para dicha \u00a0inscripci\u00f3n, a la oficina respectiva. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Inciso adicionado por el art\u00edculo 1 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del\u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 897 de 1981 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 3. Entrega \u00a0de Documentos. Los documentos requeridos para efectos de inscripci\u00f3n, \u00a0ascenso o reinscripci\u00f3n en el Escalaf\u00f3n pueden ser entregados personalmente por \u00a0el interesado o a trav\u00e9s del Director o Rector de la Instituci\u00f3n donde el \u00a0educador preste sus servicios o por intermedio del Supervisor de la Zona, a la \u00a0Oficina de Escalaf\u00f3n correspondiente, la cual los aceptar\u00e1 bajo recibo, si \u00a0estuvieren completos, con indicaci\u00f3n de la fecha y relaci\u00f3n de los documentos \u00a0entregados. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Cuando en el lugar de trabajo del educador no se disponga \u00a0del formulario oficial o solicitud de ingreso o ascenso en el escalaf\u00f3n, \u00a0distribuido por las Oficinas de Escalaf\u00f3n y las Secretar\u00edas de Educaci\u00f3n, \u00e9ste \u00a0puede ser reemplazado por solicitud en papel com\u00fan diligenciado por el educador, \u00a0el cual debe contener los datos completos solicitados en el formulario oficial. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 4. \u00a0Tramitaci\u00f3n \u00a0a trav\u00e9s del Director, Rector o Supervisor. Cuando el Educador haga entrega de todos los documentos \u00a0requeridos para inscripci\u00f3n o ascenso al Director o Rector de la instituci\u00f3n \u00a0educativa donde trabaja, o al Supervisor escolar de la Zona, dichos \u00a0funcionarios estar\u00e1n obligados a presentarlos ante la Oficina Seccional de \u00a0Escalaf\u00f3n, dentro de los diez (10) d\u00edas siguientes a la fecha de recibo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 5. \u00a0Tramitaci\u00f3n \u00a0a trav\u00e9s de planteles educativos. El Bachiller pedag\u00f3gico egresado de una Escuela Normal o \u00a0de una instituci\u00f3n de ense\u00f1anza media diversificada, puede tramitar sus \u00a0documentos a trav\u00e9s del rector de la instituci\u00f3n donde obtuvo el t\u00edtulo. Para \u00a0tal efecto, dichas instituciones enviar\u00e1n a la Oficina Seccional de Escalaf\u00f3n \u00a0correspondiente, a m\u00e1s tardar, veinte (20) d\u00edas despu\u00e9s de otorgados los \u00a0grados, los documentos completos de los educadores que hayan recibido el t\u00edtulo \u00a0y solicitado por tal conducto el tr\u00e1mite de sus documentos para ingresar al \u00a0Escalaf\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Una vez cumplido este tr\u00e1mite, la Junta Seccional de \u00a0Escalaf\u00f3n dictar\u00e1 las resoluciones de clasificaci\u00f3n de los educadores en el \u00a0Escalaf\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO II \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Ascenso \u00a0en el Escalaf\u00f3n \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a0 6. \u00a0 Documentos \u00a0requeridos para ascenso. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Para obtener ascenso en el Escalaf\u00f3n Nacional Docente, el \u00a0educador debe acreditar los siguientes documentos: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Formulario oficial a solicitud de ascenso debidamente \u00a0diligenciado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Certificaci\u00f3n original del tiempo de servicio en la \u00a0docencia, a partir de la \u00faltima clasificaci\u00f3n, expedida con base en los \u00a0correspondientes archivos por los Directores o Rectores de los establecimientos \u00a0educativos o por los funcionarios correspondientes del Ministerio de Educaci\u00f3n \u00a0o de las Secretar\u00edas de Educaci\u00f3n, quienes por este hecho se constituyen \u00a0responsables civil, penal y administrativamente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Si se tratare de colegios o instituci\u00f3n no oficial, las \u00a0certificaciones de tiempo de servicio precisar\u00e1n adem\u00e1s la autenticaci\u00f3n ante \u00a0Notario P\u00fablico y la declaraci\u00f3n juramentada del educador rendida ante el Juez \u00a0Civil de la respectiva localidad. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Los certificados de tiempo de servicio se limitar\u00e1n a \u00a0expresar el nombre e identificaci\u00f3n del educador, la fecha de ingreso y el \u00a0n\u00famero de a\u00f1os, meses y d\u00edas servidos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Si el docente no fuere de tiempo completo, el certificado \u00a0especificar\u00e1 el n\u00famero de horas-c\u00e1tedra. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Certificaci\u00f3n de cumplimiento del requisito de \u00a0capacitaci\u00f3n debidamente refrendado por la Direcci\u00f3n General de Capacitaci\u00f3n o \u00a0el Centro Experimental Piloto, cuando se requiera para el ascenso solicitado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Cuando el tiempo de servicio del docente no \u00a0oficial no aparezca certificado como se dispone en el Decreto 597 de 1980, \u00a0la Junta Seccional de Escalaf\u00f3n informar\u00e1 lo pertinente al Secretario de \u00a0Educaci\u00f3n para efecto de la imposici\u00f3n de las correspondientes sanciones. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 7. Ascenso \u00a0de Educadores titulados. El ascenso de los educadores que posen t\u00edtulo docente o \u00a0t\u00edtulo profesional Universitario diferente al de Licenciado en Ciencias de la \u00a0Educaci\u00f3n, se regir\u00e1 por lo dispuesto en el art\u00edculo 10 del Decreto \u00a0extraordinario 2277 de 1979. Cuando para obtener el ascenso requieran de un \u00a0curso de capacitaci\u00f3n, deben acreditar la certificaci\u00f3n de los cr\u00e9ditos \u00a0necesarios debidamente refrendada por la Direcci\u00f3n General de Capacitaci\u00f3n o \u00a0por el Centro Experimental Piloto, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 8. *Modificado por el \u00a0 \u00a0 \u00a0 \u00a0Decreto 217 de 2000 \u00a0nuevo texto* Los licenciados en \u00a0ciencias de la educaci\u00f3n, con dos (2) a\u00f1os de experiencia docente en el grado \u00a0(13) que no hayan sido sancionados con exclusi\u00f3n del escalaf\u00f3n docente y que \u00a0sean autores de una obra de car\u00e1cter cient\u00edfico, pedag\u00f3gico o t\u00e9cnico, \u00a0reconocida por el Ministerio de Educaci\u00f3n Nacional, o posea t\u00edtulo de postgrado \u00a0reconocido por el Gobierno Nacional, tendr\u00e1n derecho a obtener el ascenso al \u00a0grado (14). \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El tiempo de servicio en el grado \u00a0(13) se contar\u00e1 a partir de la fecha para nuevo ascenso que haya determinado la \u00a0resoluci\u00f3n de asimilaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La no exclusi\u00f3n del escalaf\u00f3n se \u00a0acreditar\u00e1 mediante certificaci\u00f3n expedida por el Presidente de la Junta \u00a0Seccional de Escalaf\u00f3n, del ente territorial en el cual preste o haya prestado \u00a0servicios el docente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Corresponde al Instituto \u00a0Colombiano para el Fomento de la Educaci\u00f3n Superior, Icfes, certificar la idoneidad \u00a0del t\u00edtulo de postgrado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota \u00a0 de Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Modificado por \u00a0art\u00edculo 1 del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 217 de 2000. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Texto \u00a0anterior* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Modificado por el \u00a0 \u00a0 \u00a0 Decreto 897 de 1981* Los \u00a0licenciados en ciencias de la educaci\u00f3n, con dos (2) a\u00f1os de experiencia \u00a0docente en el grado trece (13) que no hayan sido sancionados con exclusi\u00f3n del \u00a0Escalaf\u00f3n Docente y que sean autores de una obra de car\u00e1cter cient\u00edfico, \u00a0pedag\u00f3gico o t\u00e9cnico, reconocida por el Ministerio de Educaci\u00f3n Nacional, o \u00a0posean titulo de postgrado reconocido por el Gobierno Nacional, tendr\u00e1n derecho \u00a0a obtener el ascenso al grado catorce (14). \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El tiempo de \u00a0servicio en el grado trece (13) se contara a partir de la fecha para nuevo \u00a0ascenso que haya determinado la resoluci\u00f3n de asimilaci\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La no \u00a0exclusi\u00f3n del Escalaf\u00f3n se acreditar\u00e1 mediante certificaci\u00f3n del Ministerio de \u00a0Educaci\u00f3n Nacional. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Corresponde \u00a0al Instituto Colombiano para el Fomento de la Educaci\u00f3n Superior, ICFES, \u00a0certificar la idoneidad del t\u00edtulo de postgrado.\u201d. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Texto \u00a0inicial del Decreto 0259 de 1981* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Los licenciados en Ciencias de la Educaci\u00f3n, con dos a\u00f1os de \u00a0experiencia docente en el grado (13) que no hayan sido sancionados con \u00a0exclusi\u00f3n del escalaf\u00f3n docente y que sean autores de una obra de car\u00e1cter \u00a0cient\u00edfico, pedag\u00f3gico o t\u00e9cnico, reconocida por el Ministerio de Educaci\u00f3n \u00a0Nacional, o posean t\u00edtulo de postgrado reconocido por el Gobierno Nacional, \u00a0tendr\u00e1 derecho a obtener el ascenso al grado catorce (14).\u201d. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 9. \u00a0Ascenso \u00a0de educadores sin t\u00edtulo. El ascenso de los educadores sin t\u00edtulo docente se regir\u00e1 \u00a0por lo dispuesto en los art\u00edculos 77,78,79, 80 y 81 del Decreto \u00a0Extraordinario 2277 de 1979. Cuando para obtener el ascenso se requiera de \u00a0curso de capacitaci\u00f3n deber\u00e1 acreditarse la certificaci\u00f3n de los cr\u00e9ditos \u00a0necesarios debidamente refrendada por la Direcci\u00f3n General de Capacitaci\u00f3n o \u00a0por el Centro Experimental Piloto, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. De conformidad con lo dispuesto en los \u00a0art\u00edculos 77 y 78 citados, el tiempo de servicio para ascenso posterior a la \u00a0asimilaci\u00f3n deber\u00e1 cumplirse en el grado anterior. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 10. \u00a0Tiempo \u00a0de servicio para ascenso. Los a\u00f1os de servicio para ascenso en el escalaf\u00f3n podr\u00e1n \u00a0ser continuos o discontinuos y laborados en establecimientos educativos \u00a0oficiales y no oficiales aprobados por el Ministerio de Educaci\u00f3n Nacional. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 11. Tiempo \u00a0de servicio por hora c\u00e1tedra. El tiempo de servicio por hora-c\u00e1tedra se contabilizar\u00e1 en \u00a0la siguiente forma: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Un m\u00ednimo de doce (12) horas c\u00e1tedra semanales en el \u00a0a\u00f1o lectivo, equivalen a un a\u00f1o de servicio. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Menos de doce (12) y hasta seis (6) horas c\u00e1tedra \u00a0semanales en el a\u00f1o lectivo, equivalen a medio a\u00f1o de servicio. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Las horas c\u00e1tedra dictadas en diferentes planteles \u00a0ofcia1es y no oficiales son acumulables para efectos de lo dispuesto en los \u00a0litera1es a) y b) del presente Art\u00edculo, pero en ning\u00fan caso se computar\u00e1 como \u00a0tiempo doble para efectos de ascenso. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Las horas c\u00e1tedra dictadas en planteles no oficiales \u00a0deber\u00e1n ser acreditadas de acuerdo con el Art\u00edculo 11 del Decreto 2277 de 1979 \u00a0seg\u00fan el cual es necesaria la declaraci\u00f3n juramentada del docente ante juez \u00a0competente y los correspondientes certificados deber\u00e1n ser autenticados ante \u00a0Notario P\u00fablico. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 12. Ascenso \u00a0por t\u00edtulo. El educador escalafonado que acredite un t\u00edtulo docente o \u00a0un t\u00edtulo profesional universitario, distinto al que le sirvi\u00f3 para el ingreso \u00a0al escalaf\u00f3n, adquiere el derecho de ascenso al grado que le corresponde en \u00a0virtud del t\u00edtulo. Se except\u00faa el ascenso al grado 14 para el cual deben \u00a0reunirse los dem\u00e1s requisitos establecidos en el Art\u00edculo 10 del Decreto 2277 de 1979. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Los educadores asimilados sin t\u00edtulo docente tiene tambi\u00e9n \u00a0derecho a ascenso al grado que le corresponda en virtud del t\u00edtulo que \u00a0adquieran. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 13. Tiempo \u00a0de servicio por estudios superiores. Los educadores con t\u00edtulo docente y los profesionales con \u00a0t\u00edtulo universitario diferente al de licenciado, que obtengan un t\u00edtulo de \u00a0postgrado en educaci\u00f3n u otro t\u00edtulo universitario de nivel profesional \u00a0debidamente reconocido por el Gobierno Nacional, en los t\u00e9rminos establecidos \u00a0en el Decreto \u00a0Extraordinario 080 de 1980 y el reglamentario 3191 del mismo a\u00f1o, en una \u00a0carrera que ofrezca un mejoramiento acad\u00e9mico dentro del \u00e1rea de su \u00a0especializaci\u00f3n, se le reconocer\u00e1n tres (3) a\u00f1os de servicios para efectos de \u00a0ascenso en el escalaf\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. *Modificado \u00a0por el \u00a0 art\u00edculo 1 \u00a0 del \u00a0 \u00a0 \u00a0 \u00a0Decreto 1059 de 1989 \u00a0 \u00a0nuevo texto* La \u00a0Junta Seccional de Escalaf\u00f3n, decidir\u00e1 lo pertinente aplicando los criterios \u00a0que mediante Acuerdo, la Junta Directiva del Instituto Colombiano para el \u00a0Fomento de la Educaci\u00f3n Superior, ICFES, fije peri\u00f3dicamente para establecer \u00a0que la aprobaci\u00f3n del programa y la carrera de que se trata, representa el \u00a0mejoramiento a que hace referencia el art\u00edculo 39 del Decreto 2277 de 1979. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Texto \u00a0anterior* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Modificado por \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0art\u00edculo 3 del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 897 de 1981. \u201cLa Junta Seccional de Escalaf\u00f3n decidir\u00e1 \u00a0lo pertinente previo concepto del Instituto Colombiano para el Fomento de la \u00a0Educaci\u00f3n Superior, ICFES, expedido por solicitud del interesado, en el que \u00a0dicho Instituto certifique la aprobaci\u00f3n del programa y que la carrera de que \u00a0se trata representa el mejoramiento a que hace referencia el art\u00edculo 39 del \u00a0Decrete 2277 de 1979. El concepto del ICFES no causa honorarios y debe \u00a0expedirse dentro de los sesenta (60) d\u00edas siguientes a su solicitud.\u201d. \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Texto \u00a0inicial del par\u00e1grafo* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La Junta Seccional de Escalaf\u00f3n, decidir\u00e1 lo pertinente \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0aplicando los criterios que mediante Acuerdo, la Junta Directiva del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Instituto Colombiano para el Fomento de la Educaci\u00f3n Superior, ICFES. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAP\u00cdTULO III \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Por \u00a0tiempo de servicio por obras escritas \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 14\u00a0 *Derogado por \u00a0 el \u00a0 \u00a0 \u00a0 Decreto 385 de 1998* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0derogado por el \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0art\u00edculo 7 del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 385 de 1998 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Texto Original del Decreto 0259 de 1981* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 14. Al \u00a0educador escalafonado que sea autor de obras did\u00e1cticas, t\u00e9cnicas o cient\u00edficas \u00a0aceptadas por el Ministerio de Educaci\u00f3n Nacional, se le reconocer\u00e1n dos (2) \u00a0a\u00f1os de servicio para ascenso en el Escalaf\u00f3n por cada obra y hasta un m\u00e1ximo \u00a0de tres obras siempre que no las haya hecho valer para la inscripci\u00f3n o ascenso \u00a0con anterioridad a la vigencia del Decreto 2277 de 1979. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Para efectos del presente art\u00edculo, enti\u00e9ndese por obra \u00a0did\u00e1ctica la destinada a instruir y educar en diversos niveles del conocimiento \u00a0en donde se presente una orientaci\u00f3n pr\u00e1ctica y sin dogmatismo, en beneficio \u00a0del saber humano. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Obra cient\u00edfica o tecnol\u00f3gica, la que se elabora sobre temas de \u00a0las ramas cient\u00edficas de que tratan los programas de bachillerato y de la \u00a0ense\u00f1anza normalista o de la ense\u00f1anza t\u00e9cnica, comercial, industrial o \u00a0agr\u00edcola. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Obra pedag\u00f3gica, la que desarrolla temas pedag\u00f3gicos de utilidad \u00a0para la ense\u00f1anza y el aprendizaje en los distintos niveles del sistema \u00a0educativo. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Tales obras deber\u00e1n tener bases de investigaci\u00f3n sistem\u00e1tica o \u00a0de experiencias en el campo docente. \u00a0 Ver Ley 50 de 1986 y \u00a0Art\u00edculo 42 Decreto \u00a0Nacional 2277 de 1979. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 15. \u00a0*Derogado \u00a0por el \u00a0 \u00a0 \u00a0 Decreto 385 de 1998* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0derogado por el \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0art\u00edculo 7 del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 385 de 1998 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Texto Original del Decreto 0259 de 1981* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 15. Corresponde \u00a0a la Subdirecci\u00f3n de Desarrollo de la Educaci\u00f3n Superior Divisi\u00f3n Acad\u00e9mica \u00a0ICFES, calificar las obras did\u00e1cticas, t\u00e9cnicas o cient\u00edficas cuando estas \u00a0versen sobre temas de educaci\u00f3n superior y a la Direcci\u00f3n General de \u00a0Capacitaci\u00f3n y perfeccionamiento Docente, Curr\u00edculo y Medios Educativos del \u00a0Ministerio de Educaci\u00f3n, la calificaci\u00f3n de las obras cuando estas traten sobre \u00a0temas de educaci\u00f3n no superior.\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 16. \u00a0 *Derogado \u00a0por el \u00a0 \u00a0 \u00a0 Decreto 385 de 1998* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo derogado por el art\u00edculo 7 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 385 de 1998 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo modificado por el art\u00edculo \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a04 del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 897 de 1981 <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Texto \u00a0 Modificado por el \u00a0 \u00a0 \u00a0 Decreto 897 de 1981* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 16. \u00a0 \u00a0*Modificado por el \u00a0 \u00a0 \u00a0 Decreto 897 de 1981* Requisitos.Para efectos de la calificaci\u00f3n de la \u00a0obra, el peticionario deber\u00e1 presentar ante la entidad competente seg\u00fan el \u00a0art\u00edculo anterior, los siguientes documentos: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Memorial de solicitud. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Certificado de clasificaci\u00f3n del \u00a0peticionario en el Escalaf\u00f3n expedido por el Jefe de la respectiva oficina \u00a0seccional, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Tres ejemplares de la obra \u00a0debidamente empastados. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4. \u00a0 Certificado de registro de autor\u00eda de la obra en la Oficina de Propiedad \u00a0 Intelectual expedido por el Ministerio de Gobierno u oficina que haga sus veces. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El estudio y concepto no causan \u00a0honorarios y deber\u00e1n producirse dentro de los sesenta (60) d\u00edas siguientes a la \u00a0solicitud. En caso de que la obra tuviere m\u00e1s de doscientas p\u00e1ginas, el \u00a0anterior t\u00e9rmino se aumentara a raz\u00f3n de un d\u00eda por cada veinticinco hojas. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Si la obra hubiere sido \u00a0escrita por dos o m\u00e1s educadores, el reconocimiento del tiempo de servicio se \u00a0efectuara proporcionalmente entre los distintos autores inscritos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Texto Original del Decreto 0259 de 1981* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 16. Para efectos de la calificaci\u00f3n de la obra, \u00a0 el peticionario deber\u00e1 presentar ante la entidad competente seg\u00fan el Art\u00edculo \u00a0 anterior, los siguientes documentos: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Memorial de solicitud. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Un ejemplar de las obras que contengan un m\u00ednimo de 200 \u00a0p\u00e1ginas con dimensiones no menor de 30&#215;20 cent\u00edmetros que se conservar\u00e1 en la \u00a0biblioteca de la ciudad que hace el reconocimiento. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Certificado de clasificaci\u00f3n en el Escalaf\u00f3n expedida por la \u00a0respectiva Junta Seccional. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4. Certificado de registro de autor\u00eda de la obra en la Oficina \u00a0de Propiedad Intelectual expedido por el Ministerio de Gobierno. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 17 \u00a0 \u00a0*Derogado \u00a0por el \u00a0 \u00a0 \u00a0 Decreto 897 de 1981* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo derogado por el art\u00edculo 7 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 385 de 1998 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Texto Original del Decreto 0259 de 1981* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 17. \u00a0 Corresponde \u00a0a la Junta Seccional de Escalaf\u00f3n respectiva el reconocimiento del tiempo de \u00a0servicio por la obra u obras calificadas mediante providencia administrativa, \u00a0previa presentaci\u00f3n del concepto emitido por la entidad competente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO IV \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Servicios \u00a0prestados en escuelas unitarias, \u00e1reas rurales, poblaciones apartadas y \u00a0Territorios Nacionales. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculos 18. \u00a0 \u00a0Tiempo doble. *Modificado \u00a0por el \u00a0 \u00a0 \u00a0 Decreto 2669 de 1981 \u00a0 nuevo texto*\u00a0 A los \u00a0educadores con t\u00edtulo docente que a partir de la fecha de expedici\u00f3n del Decreto \u00a0extraordinario 2277 de 1979 desempe\u00f1en sus funciones en escuelas unitarias, \u00a0\u00e1reas rurales de dif\u00edcil acceso y poblaciones apartadas, se les tendr\u00e1 en cuenta \u00a0como doble el tiempo de servicio para ascenso o el Escalaf\u00f3n. Para efectos de \u00a0lo dispuesto en este art\u00edculo, establ\u00e9cense los siguientes criterios: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Denom\u00ednase escuela unitaria o escuela nueva el \u00a0establecimiento oficial que funciona con uno o dos maestros para atender los \u00a0tres o cinco grados de educaci\u00f3n b\u00e1sica primaria; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Denom\u00ednanse \u00e1reas rurales de dif\u00edcil acceso y \u00a0poblaciones apartadas aquellos Corregimientos, veredas, Inspecciones de Polic\u00eda \u00a0y regiones con comunidades que tenga hasta 1.500 habitantes, a los cuales deba \u00a0trasladarse el docente, en raz\u00f3n de su cargo, por zonas escarpadas, cenagosas, \u00a0selv\u00e1ticas o declaradas de orden p\u00fablico y que por estas circunstancias tengan \u00a0que fijar su residencia en el sitio de trabajo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo derogado por el art\u00edculo 1 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 2669 de 1981 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Texto Original del Decreto 0259 de 1981* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 18. \u00a0 \u00a0 Tiempo \u00a0doble. A los educadores con t\u00edtulo docente que a partir de la fecha de \u00a0expedici\u00f3n del Decreto \u00a0extraordinario 2277 de 1979, desempe\u00f1en sus funciones en escuelas \u00a0unitarias, \u00e1reas rurales de dif\u00edcil acceso y poblaciones apartadas, se les \u00a0tendr\u00e1n en cuenta como doble tiempo de servicio para ascenso en el Escalaf\u00f3n. Para \u00a0efectos de lo dispuesto en este art\u00edculo, establ\u00e9cese los siguientes criterios: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Denominanse escuela unitaria oficial que funciona con un solo \u00a0maestro que atiende varios cursos, grupos o grados escolares; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Denominanse \u00e1reas rurales de dif\u00edcil acceso las veredas, corregimientos, \u00a0inspecciones de polic\u00eda y, adem\u00e1s aquellas regiones colombianas a las cuales debe \u00a0trasladarse el docente en raz\u00f3n de su cargo, en rudimentarios medios de \u00a0trasporte o a pie en zonas escarpadas, cenagosas, selv\u00e1ticas o declaradas de \u00a0orden publico; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Denominanse regiones apartadas aquellas que tienen una de las \u00a0siguientes caracter\u00edsticas; \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Carecen de acceso por v\u00eda terrestre o solamente disponen de v\u00eda \u00a0carreteable para veh\u00edculos de tracci\u00f3n doble. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Carecen de servicios p\u00fablicos, es decir, no cuentan con luz \u00a0permanente, acueducto o alcantarillado y carecen de telefon\u00eda. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 19. El tiempo de servicio prestado por \u00a0los educadores en los Territorios Nacionales se les tomar\u00e1 como doble para \u00a0efectos de ascenso en el Escalaf\u00f3n. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 20. \u00a0 \u00a0Determinaci\u00f3n de \u00e1reas \u00a0rurales. *Modificado \u00a0por el \u00a0 \u00a0 \u00a0 Decreto 2669 de 1981 \u00a0 nuevo texto* \u00a0 El delegado del Ministerio de Educaci\u00f3n Nacional ante la Junta \u00a0Administradora del Fondo Educativo Regional, en asocio con el coordinador del \u00a0mapa educativo y el Director del Centro Experimental Piloto, elaborar\u00e1n, en consulta \u00a0con el Instituto Agust\u00edn Codazzi, un listado de las escuelas unitarias o nuevas \u00a0y de los planteles ubicados en \u00e1reas rurales de dif\u00edcil acceso y de las \u00a0poblaciones apartadas, teniendo en cuenta los criterios establecidos en el \u00a0presente Decreto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Estos listados ser\u00e1n presentados a la Junta Seccional de \u00a0Escalaf\u00f3n para que determine, mediante resoluci\u00f3n motivada, cu\u00e1les \u00a0establecimientos educativos quedan cobijados dentro de esta calificaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Las resoluciones deben ser remitidas a la Junta Nacional \u00a0de Escalaf\u00f3n para su refrendaci\u00f3n, requisito sin el cual no podr\u00e1 computarse \u00a0tiempo de servicio doble. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo derogado por el art\u00edculo 2 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 2669 de 1981 <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0*Texto \u00a0 Original del Decreto 0259 de 1981* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 20. \u00a0 \u00a0 Determinaci\u00f3n de \u00e1reas rurales. El Delegado del Ministerio de Educaci\u00f3n Nacional ante \u00a0la Junta Administradora del Fondo Educativo Regional, elaborar\u00e1 en consulta con \u00a0el DANE o con la Oficina de Planeaci\u00f3n del Departamento o con el Instituto Agust\u00edn \u00a0Codazzi, un listado de las escuelas unitarias y otro de los planteles ubicados \u00a0en \u00e1reas rurales de dif\u00edcil acceso y en poblaciones apartadas tendiendo en \u00a0cuenta los criterios establecidos en el presente Decreto. Estos listados ser\u00e1n \u00a0presentados a la Junta Seccional de Escalaf\u00f3n para que se determine, mediante \u00a0resoluci\u00f3n motivada cuales establecimientos educativos quedan cobijados dentro \u00a0de esta norma. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Las resoluciones deben ser remitidas a la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Junta Nacional de Escalaf\u00f3n para su refrendaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAP\u00cdTULO V \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 21. \u00a0T\u00e9rminos \u00a0para decidir y vigencia de los ascensos. Las solicitudes de ascenso en el escalaf\u00f3n nacional \u00a0docente, ser\u00e1n resueltos por las juntas seccionales dentro de los sesenta (60) \u00a0d\u00edas siguientes al recibo de la respectiva documentaci\u00f3n, siempre y cuando \u00a0llene todos los requisitos exigidos en el Art\u00edculo 6\u00ba. El ascenso surte efectos \u00a0fiscales a partir de la fecha de la resoluci\u00f3n que lo ordena, y en todo caso, a \u00a0partir del vencimiento del plazo de sesenta d\u00edas, al recibo de la documentaci\u00f3n \u00a0completa en los t\u00e9rminos del art\u00edculo 21 del Decreto 2277 de 1979. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 22. Vigencia \u00a0retardada. En los t\u00e9rminos del anterior Art\u00edculo, si la documentaci\u00f3n \u00a0es devuelta por incompleta o porque faltare acreditar el curso de capacitaci\u00f3n, \u00a0el t\u00e9rmino de que se viene tratando solo empezar\u00e1 a correr en la fecha \u00a0posterior en que se subsanen las deficiencias observadas por la Oficina de \u00a0Escalaf\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La resoluci\u00f3n que decrete un ascenso dejar\u00e1 expresa \u00a0constancia de la fecha a partir de la cual se surtan efectos fiscales, de \u00a0acuerdo con lo expresado en este art\u00edculo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 23. \u00a0 *Modificado \u00a0por el Decreto 2480 de 1986, \u00a0 nuevo texto* El tiempo de servicio para el nuevo ascenso se contar\u00e1 a partir de la \u00a0fecha en que se hubieren cumplido todos los requisitos para el ascenso \u00a0inmediatamente anterior: tiempo de servicio y curso de capacitaci\u00f3n si fuere el \u00a0caso. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El tiempo de servicio laborado por el \u00a0docente, que \u00e9ste acredite, con el lleno de las formalidades del caso, debe \u00a0contabilizarse y de este hecho quedar\u00e1 constancia en la correspondiente \u00a0resoluci\u00f3n. En ning\u00fan caso el docente perder\u00e1 el tiempo de servicio laborado. \u00a0Pero su demora u omisi\u00f3n en solicitar el ascenso solo le afectar\u00e1 para la \u00a0determinaci\u00f3n de la fecha de efectos fiscales. Si la documentaci\u00f3n presentada \u00a0por un docente no re\u00fane los requisitos exigidos, se proceder\u00e1 a su devoluci\u00f3n \u00a0para que subsane la omisi\u00f3n. Corregida la deficiencia observada se empezar\u00e1 a \u00a0contar el t\u00e9rmino de sesenta (60) d\u00edas calendario, como m\u00e1ximo, para la \u00a0expedici\u00f3n de la resoluci\u00f3n de ascenso. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Cuando por acumulaci\u00f3n de requisitos un \u00a0docente deba ascender varios grados, la Junta Seccional puede decidir dichos \u00a0ascensos mediante un solo acto administrativo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo derogado por el art\u00edculo \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a074 del \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 2669 de 1981 <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0*Texto \u00a0 Original del Decreto 0259 de 1981* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 23. Tiempo de servicio para el nuevo ascenso. \u00a0(3) El tiempo de servicio para el nuevo escalaf\u00f3n se contar\u00e1 a partir de la \u00a0fecha en que se hubieren cumplido todos los requisitos para el ascenso \u00a0inmediatamente anterior; tiempo de servicio y curso de capacitaci\u00f3n, si fuere \u00a0el caso. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">En consecuencia, cuando un ascenso se retrase \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0por no haberse acreditado curso de capacitaci\u00f3n o por cualquier otro \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0motivo justificado el tiempo para el nuevo ascenso, del que deber\u00e1 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0dejarse constancia en la resoluci\u00f3n, s\u00f3lo podr\u00e1 contarse a partir de la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0fecha en que se subsan\u00f3 la omisi\u00f3n y ser\u00e1 el de la resoluci\u00f3n respectiva \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0o el m\u00e1ximo de sesenta d\u00edas contados a partir del recibo de la \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0documentaci\u00f3n completa. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 24. Tiempo de servicio sobrante. Cuando un educador obtenga un ascenso en virtud de lo dispuesto \u00a0en los art\u00edculos 12, 13 y 14 de este Decreto y le sobra tiempo de servicio en \u00a0el grado anterior, este tiempo se tendr\u00e1 en cuenta para el ascenso posterior. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO VI \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Capitulo \u00a0derogado por el art\u00edculo 30 del \u00a0 \u00a0 \u00a0 Decreto 709 de 1996* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Experiencia docente y cursos de \u00a0capacitaci\u00f3n \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 25. \u00a0Cursos \u00a0de capacitaci\u00f3n no utilizados. Para los efectos \u00a0previstos en el art\u00edculo 73 del Decreto 2277 de 1379; \u00a0el educador que desee hacer uso \u00a0para ascenso de un curso de \u00a0capacitaci\u00f3n no utilizado con anterioridad, deber\u00e1 \u00a0presentar los siguientes documentos: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Certificado del curso realizado, debidamente refrendado par \u00a0la Direcci\u00f3n General de Capacitaci\u00f3n del Ministerio de Educaci\u00f3n o por el Centro Experimental Piloto \u00a0respectivo; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Certificaci\u00f3n de la Oficina de Escalaf\u00f3n que conserve su expediente sobre el hecho de no aparecer dicho curso \u00a0acreditado para ascenso anterior. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 26. Experiencia \u00a0docente no utilizada. El educador que prest\u00f3 servicios docentes con anterioridad a la \u00a0asimilaci\u00f3n y no hab\u00eda podido obtener o presentar \u00a0la certificaci\u00f3n correspondiente, \u00a0tendr\u00e1 oportunidad de hacerlo en el momento de presentar su primera solicitud de ascenso despu\u00e9s de la \u00a0asimilaci\u00f3n. Precluida esta oportunidad no se tomar\u00e1 en cuenta ninguna \u00a0experiencia docente que no corresponde \u00a0al grado anterior al cual se aspira a ascender. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Lo anterior, no autoriza \u00a0la revisi\u00f3n de situaciones jur\u00eddicas \u00a0individuales consolidadas conforme a derecho. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">En igual forma podr\u00e1 procederse en los casos en que un educador \u00a0fue restituido a su cargo por \u00a0sentencia ejecutoriada de lo Contencioso Administrativo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 27. \u00a0Documentaci\u00f3n. Para efecto de lo dispuesto en \u00a0el art\u00edculo anterior; el educador \u00a0deber\u00e1 presentar los siguientes documentos: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Memorial de solicitud; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) La certificaci\u00f3n de los servicios prestados en la forma como se dispone en este Decreto, \u00a0seg\u00fan sea servicio oficial y no oficial; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Copia aut\u00e9ntica de la providencia judicial con a constancia de su ejecutoria, cuando fuere el \u00a0caso. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 28 \u00a0 \u00a0Convalidaci\u00f3n de cursos de capacitaci\u00f3n. Los educadores que est\u00e9n \u00a0realizando estudios conducentes a un \u00a0t\u00edtulo docente podr\u00e1n hacerlos valer como curso para ascenso en el Escalaf\u00f3n por una sola \u00a0vez, conformidad con lo que a continuaci\u00f3n se establece: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) El docente que se encuentre adelantando estudios de nivel \u00a0superior o estudios de postgrado, presentar\u00e1 a la Junta Seccional de Escalaf\u00f3n un certificado expedido por la \u00a0instituci\u00f3n donde estudia, refrendado por la Direcci\u00f3n General de Capacitaci\u00f3n \u00a0y Perfeccionamiento Docente, Curriculo y Medios Educativos del Ministerio de \u00a0Educaci\u00f3n o por el respectivo Centro \u00a0Experimental Piloto, en el cual conste \u00a0que ha aprobado dos (2) semestres o un a\u00f1o acad\u00e9mico; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) El educador que se encuentre haciendo cursos de profesionalizaci\u00f3n para obtener el t\u00edtulo de bachiller pedag\u00f3gico, presentara; a la \u00a0Junta Seccional de Escalaf\u00f3n un certificado \u00a0expedido por la entidad donde estudia, \u00a0refrendado por la Direcci\u00f3n General de Capacitaci\u00f3n y Perfeccionamiento \u00a0Docente, Curr\u00edculo y Medios Educativos del Ministerio de Educaci\u00f3n o por el \u00a0Centro Experimental Piloto respectivo, en el \u00a0cual conste que ha terminado y aprobado una etapa de profesionalizaci\u00f3n de 240 \u00a0horas; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) El educador que este \u00a0adelantando estudios regulares conducentes a un t\u00edtulo de bachiller pedag\u00f3gico, \u00a0presentar\u00e1 a la Junta Seccional de \u00a0Escalaf\u00f3n un certificado expedido por el establecimiento donde estudia, \u00a0refrendado por la Direcci\u00f3n General de \u00a0Capacitaci\u00f3n y Perfeccionamiento Docente, Curr\u00edculos y Medios Educativos del \u00a0Ministerio de Educaci\u00f3n Nacional o por el Centro \u00a0Experimental Piloto, en el cual conste \u00a0que ha aprobado y terminado un a\u00f1o de estudio. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 29. Aplazamiento \u00a0de curso. En aquellas entidades territoriales donde no est\u00e1n organizados \u00a0los cursos de capacitaci\u00f3n por no estar en funcionamiento los Centros \u00a0Experimentales Pilotos, las Juntas \u00a0Seccionales de Escalaf\u00f3n podr\u00e1n expedir una resoluci\u00f3n aplazando la exigencia \u00a0del curso como requisito para ascenso, \u00a0con la obligaci\u00f3n para el educador de cumplir tal requisito en el siguiente ascenso. Dicha resoluci\u00f3n \u00a0deber\u00e1 ser aprobada por la Junta Nacional de Escalaf\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Adem\u00e1s de lo dispuesto en el \u00a0inciso anterior, en cada resoluci\u00f3n de ascenso de los educadores que se acojan \u00a0a este aplazamiento se deber\u00e1 dejar la \u00a0constancia pertinente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Lo anterior ser\u00e1 aplicable durante el a\u00f1o de 1901, pero no impide que los \u00a0educadores que lo deseen pueden \u00a0realizar el curso de capacitaci\u00f3n en cualquier instituci\u00f3n oficial y no oficial \u00a0legalmente autorizada al efecto. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 30. Vigencia. Este Decreto rige a partir de la fecha de su expedici\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Publ\u00edquese y C\u00famplase. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Dado en Bogot\u00e1, D. E., a \u00a06 de febrero de 1981. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">VICTOR MOSQUERA CHAUX \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Educaci\u00f3n Nacional, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Guillermo \u00a0Angulo G\u00f3mez<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-15794","post","type-post","status-publish","format-standard","hentry","category-decretos-1981"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/15794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=15794"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/15794\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=15794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=15794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=15794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}