{"id":15828,"date":"2023-07-07T19:42:30","date_gmt":"2023-07-07T19:42:30","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-2887-de-1981\/"},"modified":"2023-07-07T19:42:30","modified_gmt":"2023-07-07T19:42:30","slug":"decreto-2887-de-1981","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-2887-de-1981\/","title":{"rendered":"DECRETO 2887 DE 1981"},"content":{"rendered":"\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETO 2887 DE 1981 <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(octubre 19) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">por el cual se reglamenta los art\u00edculos 23 \u00a0y 122 del Decreto \u00a0extraordinario 294 de 1973. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Nota 1: Derogado por el Decreto 3077 de 1989, \u00a0art\u00edculo 71. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Nota 2: Modificado por el Decreto 1549 de 1983. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Presidente de la Rep\u00fablica \u00a0de Colombia, en ejercicio de las facultades que le confiere el ordinal 3\u00b0 del \u00a0art\u00edculo 120 de la Constituci\u00f3n Nacional, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETA: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 1\u00b0 Las obligaciones \u00a0pendientes de pago en las oficinas de manejo a 31 de diciembre denominadas \u00a0reservas de caja y las reservas de apropiaci\u00f3n constituidas seg\u00fan lo dispuesto \u00a0en el art\u00edculo 122 del Decreto \u00a0extraordinario 294 de 1973, ser\u00e1n las \u00fanicas que se constituyan como \u00a0recursos del balance de los establecimientos p\u00fablicos con apropiaciones del \u00a0Presupuesto Nacional para la respectiva vigencia. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 2\u00b0 Modificado por el Decreto 1549 de 1983, \u00a0art\u00edculo 1\u00ba. Las reservas con aportes del presupuesto nacional conformadas \u00a0por la entidad con la aprobaci\u00f3n del auditor fiscal, se ejecutar\u00e1n hasta el 31 \u00a0de diciembre del a\u00f1o en que fueran constituidas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Las reservas de apropiaci\u00f3n \u00a0con aportes del presupuesto nacional certificadas por la Contralor\u00eda General de \u00a0la Rep\u00fablica, previo acuerdo especial de la Direcci\u00f3n General del Presupuesto, \u00a0se ejecutar\u00e1n hasta el 31 de diciembre del a\u00f1o en que fueran constituidas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Texto inicial del art\u00edculo 2\u00ba.: \u201cLas reservas de caja que hubieren quedado incluidas en \u00a0los recursos del balance de un establecimiento p\u00fablico se ejecutar\u00e1n en la \u00a0vigencia siguiente hasta el 1\u00b0 de junio, y las reservas de apropiaci\u00f3n, previa \u00a0ratificaci\u00f3n, mediante acuerdo mensual especial de la Direcci\u00f3n General del \u00a0Presupuesto, hasta el 31 de diciembre del a\u00f1o en que fueron constituidas.\u201d. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 3\u00b0 Para efectos de la \u00a0ejecuci\u00f3n y la contabilidad presupuestal de las reservas de caja y apropiaci\u00f3n \u00a0de una determinada vigencia, las entidades a que s refiere este Decreto deber\u00e1n \u00a0llevar un libro en el cual se indique claramente el art\u00edculo presupuestal, el \u00a0objeto del gasto, el monto de la obligaci\u00f3n, el n\u00famero, fecha y cuant\u00eda del \u00a0documento de pago y lo saldos respectivos. Solamente se contabilizar\u00e1n como \u00a0reservas las que hayan sido aprobadas por la Contralor\u00eda General de la \u00a0Rep\u00fablica, y en el caso de las reservas de apropiaci\u00f3n, se afectar\u00e1n a medida \u00a0que sean ratificadas mediante acuerdo mensual especial por la Direcci\u00f3n General \u00a0del Presupuesto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 4\u00b0 A partir de la \u00a0vigencia de este Decreto, los establecimientos p\u00fablicos del orden nacional \u00a0deber\u00e1n reintegrar a la Direcci\u00f3n General de Tesorer\u00eda los recursos del \u00a0Presupuesto Nacional recibidos en vigencias anteriores que no est\u00e9n debidamente \u00a0comprometidos y no se hayan constituido como reservas de caja o de apropiaci\u00f3n. \u00a0Para la liquidaci\u00f3n del ejercicio fiscal de 1981 y siguientes, los reintegros a \u00a0la Direcci\u00f3n General de Tesorer\u00eda se efectuar\u00e1 a m\u00e1s tardar el 1\u00b0 de marzo de \u00a0cada a\u00f1o. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 5\u00b0 El incumplimiento a \u00a0lo previsto en la presente disposici\u00f3n, dar\u00e1 lugar a la aplicaci\u00f3n de las \u00a0sanciones contempladas en el articulo 165 del-Decreto ley 294 de \u00a01073. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 6\u00b0 El presente Decreto \u00a0rige a partir de la fecha de su expedici\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Dado en Bogot\u00e1, D. E., a \u00a0octubre 19 de 1981. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">JULIO CESAR TURBAY AYALA \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Hacienda y \u00a0Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Eduardo Wiesner Dur\u00e1n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 DECRETO 2887 DE 1981 (octubre 19) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 por el cual se reglamenta los art\u00edculos 23 \u00a0y 122 del Decreto \u00a0extraordinario 294 de 1973. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Nota 1: Derogado por el Decreto 3077 de 1989, \u00a0art\u00edculo 71. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Nota 2: Modificado por el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-15828","post","type-post","status-publish","format-standard","hentry","category-decretos-1981"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/15828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=15828"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/15828\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=15828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=15828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=15828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}