{"id":15967,"date":"2023-07-07T19:42:39","date_gmt":"2023-07-07T19:42:39","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-54-de-1981\/"},"modified":"2023-07-07T19:42:39","modified_gmt":"2023-07-07T19:42:39","slug":"decreto-54-de-1981","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-54-de-1981\/","title":{"rendered":"DECRETO 54 DE 1981"},"content":{"rendered":"\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETO 54 DE 1981 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(enero 15 \u00a0 de 1981) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">por el cual se dictan \u00a0medidas para prevenir el contrabando \u00a0 y lograr un adecuado abastecimiento interno de az\u00facar. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Derogado \u00a0 por el \u00a0 Decreto 954 de 1996, \u00a0art\u00edculo 2\u00ba. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Derogado \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0parcialmente por el \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 60 de 1985. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Presidente \u00a0de la Rep\u00fablica de Colombia, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">en uso de sus atribuciones constitucionales y de \u00a0las especiales que le confieren la Ley 7\u00aa de 1943, los \u00a0Decretos 3092 de 1968 (Ley 48 de 1968) y 133 \u00a0de 1976, y el \u00a0 Estatuto \u00a0Penal Aduanero; \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETA \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO \u00a0I \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Cuotas de abastecimiento. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a01. El Ministerio de Agricultura establecer\u00e1 las cuotas de producci\u00f3n de az\u00facar \u00a0que los ingenios est\u00e1n obligados a vender al Instituto de Mercadeo Agropecuario \u00a0IDEMA, con el objeto de contribuir al adecuado abastecimiento \u00a0y regulaci\u00f3n de mercado interno cuando \u00a0a juicio del Ministerio se justifique \u00a0tal medida. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 2. \u00a0El Instituto de Mercadeo Agropecuario IDEMA, con las cantidades de az\u00facar que le vendan los ingenios, deber\u00e1 atender \u00a0preferentemente aquellos sectores del pa\u00eds \u00a0en los cuales se presenten \u00a0dificultades de abastecimiento, bien por razones \u00a0de su localizaci\u00f3n o por factores anormales que incidan en el mercado regional. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a03. Dentro de las cuotas de abastecimiento de que trata el art\u00edculo 1\u00ba, se incluir\u00e1 un \u00a0porcentaje de la producci\u00f3n que los \u00a0ingenios entregan a los ca\u00f1icultores \u00a0o a terceros en virtud de contratos \u00a0en los cuales se pactan pagos en especie. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Los \u00a0ingenios est\u00e1n obligados a retener y entregar al IDEMA las cuotas de az\u00facar que les \u00a0corresponda a los ca\u00f1icultores y \u00a0terceros, por la parte de producci\u00f3n que reciban en pago. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a04. El Ministerio de Agricultura abrir\u00e1 un libro en el cual registrar\u00e1 todos los contratos celebrados o que se celebren \u00a0por los ingenios con las personas naturales, jur\u00eddicas sociedades de hecho, \u00a0filiales etc., que reciban pagos en especie o en dinero de los ingenios, \u00a0registrando el nombre del predio, de la sociedad, de la persona natural, la \u00a0filial, etc., tipo de contrato \u00e1rea dedicada a ca\u00f1a de az\u00facar, \u00a0para proveer el ingenio, \u00a0forma, t\u00e9rmino y modalidad de pago, \u00a0precio de las ca\u00f1as por tonelada, plazo del contrato, pr\u00f3rroga de este. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a05. Los ingenios azucareros proceder\u00e1n, dentro del t\u00e9rmino de quince d\u00edas \u00a0contados a partir de la vigencia del presente Decreto, \u00a0a remitir al Ministerio de Agricultura un informe mensual sobre los vol\u00famenes de producci\u00f3n de az\u00facar, las \u00a0existencias en bodegas o en tr\u00e1nsito, las ventas, los pagos en especie realizados en el curso \u00a0del mes anterior, indicando cuando, \u00a0menos, los nombres de las personas naturales a jur\u00eddicas a las cuales se lea hubiere vendido o entregado az\u00facar, los lugares de destino, los nombres \u00a0de las empresas de transporte o de los \u00a0propietarios de veh\u00edculos en los cuales se traslada el producto, la destinaci\u00f3n probable del \u00a0mismo y cualquier otro dato que permita establecer su utilizaci\u00f3n \u00a0final. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Igual \u00a0obligaci\u00f3n tendr\u00e1n los distribuidores mayoristas, las exportadores, las \u00a0personas naturales o jur\u00eddicas que reciban az\u00facar como pago en especie en virtud de los contratos celebrados con los ingenios \u00a0y las f\u00e1bricas o empresas que adquieran este producto como insumo importante \u00a0para su producci\u00f3n industrial. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. \u00a0El Ministerio de Agricultura elaborar\u00e1 los formularios que deben utilizar las entidades \u00a0o personas para suministrar la informaci\u00f3n de que trata el presente Decreto \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a06. El Ministerio de Agricultura como las dem\u00e1s \u00a0 autoridades administrativas del orden \u00a0nacional, departamental y municipal, podr\u00e1 adelantar las investigaciones, \u00a0imponer las sanciones y realizar u ordenarles decomisos a que den lugar las \u00a0infracciones al presente Decreto por raz\u00f3n de acaparamiento o indebida \u00a0retenci\u00f3n del az\u00facar, de acuerdo con los procedimientos y en los t\u00e9rminos de \u00a0las facultades que le otorga la ley, sin perjuicio de las dem\u00e1s sanciones a que \u00a0pueden dar lugar dichos actos en virtud de competencias otorgadas a otros \u00a0organismos administrativos o jurisdiccionales. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO \u00a0II \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0De las exportaciones. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a07. Las exportaciones de az\u00facar de producci\u00f3n nacional \u00fanicamente podr\u00e1n \u00a0realizarse por los ingenios productores y los exportadores debidamente \u00a0registrados ante el Instituto Colombiano de Comercio Exterior. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a08. \u00danicamente podr\u00e1n exportarse los vol\u00famenes de az\u00facar que no se hayan destinado \u00a0por el Ministerio de Agricultura al abastecimiento nacional. Los \u00a0exportadores est\u00e1n obligados a incluir en las exportaciones de az\u00facar un porcentaje \u00a0procedente de quienes reciban pago en especie de los ingenios, equivalente a la proporci\u00f3n que les \u00a0corresponda despu\u00e9s de deducida la cantidad con que deben contribuir al \u00a0abastecimiento nacional. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. El Instituto \u00a0Colombiano de Comercio \u00a0Exterior, INCOMEX, condicionar\u00e1 la aprobaci\u00f3n de las licencias de exportaciones \u00a0a las exigencias previstas en el presente art\u00edculo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 9. *Derogado por el \u00a0 \u00a0 Decreto 60 de 1985* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de \u00a0 Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Derogado \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0parcialmente por el \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 60 de 1985. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0*Texto Original del Decreto 0054 de 1981* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 9. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0La exportaci\u00f3n de az\u00facar s\u00f3lo podr\u00e1 realizarse por el Puerto de \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Buenaventura por aquellos otros que en el futuro autorice el Gobierno \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Nacional. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 10. *Derogado por \u00a0el \u00a0 \u00a0 Decreto 60 de 1985* \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">*Nota de \u00a0 Vigencia* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Derogado \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0parcialmente por el \u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Decreto 60 de 1985. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0*Texto Original del Decreto 0054 de 1981* \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 10. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 S\u00f3lo \u00a0podr\u00e1 exportarse az\u00facar de ca\u00f1a cruda \u00a0en estado s\u00f3lido a granel, en bruto, con 85% a 97.5% \u00a0de sacarosa, con una polarizaci\u00f3n m\u00e1xima de 97.5 grados y en cuya elaboraci\u00f3n no se hayan utilizado elementos \u00a0de blanqueo. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El az\u00facar en tales condiciones se presenta \u00a0como un producto de color carmelita, con grano grueso recubierto por \u00a0una pel\u00edcula de melaza. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO III \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Del almacenamiento y transportes. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 11. \u00a0 Los cargamentos de az\u00facar con destino a la \u00a0exportaci\u00f3n solo podr\u00e1n almacenarse en \u00a0bodegas oficiales. Al presentarse el manifiesto de \u00a0exportaci\u00f3n la Aduana tomar\u00e1 muestra del cargamento para practicar un examen merci\u00f3logo a fin de establecer si el \u00a0producto re\u00fane las caracter\u00edsticas de az\u00facar para exportaci\u00f3n. Solo cuando el dictamen que al efecto produzca la Aduana fuere favorable, podr\u00e1 autorizarse el \u00a0embarque. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Articulo 12. El transporte de \u00a0az\u00facar con destino a exportaci\u00f3n s\u00f3lo \u00a0podr\u00e1 realizarse por las empresas de servicios p\u00fablicos que tengan constituida fianza para transportar este \u00a0producto y que est\u00e9n debidamente inscritas ante la Direcci\u00f3n General de Aduanas. Igualmente podr\u00e1 realizarse veh\u00edculos particulares \u00a0cuando los due\u00f1os de estos tambi\u00e9n lo \u00a0sean del cargamento y est\u00e9n inscritos, ante la Direcci\u00f3n General de Aduanas. \u00a0Los ingenios que tengan medios de transporte deber\u00e1n inscribirlos ante la misma Direcci\u00f3n General de Aduanas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a013. Todo cargamento de az\u00facar con destino a la exportaci\u00f3n debe estar amparado por una \u00a0gu\u00eda de tr\u00e1nsito expedida de acuerdo con los t\u00e9rminos y condiciones que para tal efecto establezca \u00a0el Ministerio de Obras P\u00fablicas \u00a0y Transporte. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 14. La distribuci\u00f3n, mercadeo y transporte del az\u00facar en las zonas costaneras y fronterizas ser\u00e1 supervisados por los Alcaldes Municipales. Tales funcionarios \u00a0adem\u00e1s, est\u00e1n autorizados para vigilar y controlar el mercadeo y venta del az\u00facar en las \u00e1reas a que se \u00a0refiere el presente art\u00edculo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 15. En las \u00a0zonas territoriales, fronterizas o costaneras \u00a0que determine la Direcci\u00f3n General de Aduanas, las plantillas o gu\u00edas de \u00a0movilizaci\u00f3n de az\u00facar deber\u00e1n ser visadas selladas por los funcionarios de \u00a0Aduana o los Comandos de Polic\u00edas de \u00a0lugares o retienes por donde se transporte el producto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Articulo 16. Queda prohibido \u00a0el transporte de az\u00facar en el territorio nacional por medio de cabotaje \u00a0mar\u00edtimo, o transporte a\u00e9reo. El abastecimiento de los sectores que sea \u00a0indispensable realizar por v\u00eda acu\u00e1tica o a\u00e9rea, se har\u00e1 en naves o aeronaves \u00a0oficiales o privadas bajo la vigilancia del Resguardo Nacional de Aduanas, la \u00a0Armada Nacional y\/o la polic\u00eda nacional. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO IV \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0De las sanciones. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 17. \u00a0 Los armadores, \u00a0agentes mar\u00edtimo, capitanes de naves, tripulantes y cualquier persona que, en \u00a0una u otra forma, infrinjan lo dispuesto en el presente Decreto, incurrir\u00e1n \u00a0entre otras sanciones en las siguientes, que ser\u00e1n impuestas privativamente por \u00a0la Direcci\u00f3n General Mar\u00edtima y Portuaria, sin perjuicio de las sanciones \u00a0penales a que hubiere lugar: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Cancelaci\u00f3n o suspensi\u00f3n \u00a0del tr\u00e1fico concedido al armador, hasta por un a\u00f1o. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Cancelaci\u00f3n o suspensi\u00f3n de \u00a0la patente de navegaci\u00f3n de la nave, hasta por un a\u00f1o. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Cancelaci\u00f3n o suspensi\u00f3n de \u00a0las licencias de navegaci\u00f3n de los capitanes o tripulantes, hasta por un a\u00f1o. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Cancelaci\u00f3n o suspensi\u00f3n de \u00a0la licencia de agente mar\u00edtimo, hasta por un a\u00f1o. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Prohibici\u00f3n permanente o \u00a0temporal para ejercer el comercio en cualquier actividad mar\u00edtima, hasta por \u00a0tres a\u00f1os. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">f) Multas sucesivas a favor \u00a0del Tesoro Nacional, en cuant\u00eda de cincuenta mil pesos ($ 50.000.00) a dos \u00a0millones de pesos ($ 2000.000.00) moneda corriente, \u00a0convertibles en arresto en la proporci\u00f3n legal. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 18. Por denuncia del \u00a0hecho o de manera oficiosa, la Direcci\u00f3n General Mar\u00edtima o Portuaria conocer\u00e1 \u00a0y podr\u00e1 imponer las sanciones del caso en el evento de que se incurra en la \u00a0violaci\u00f3n de las prohibiciones establecidas en el presente Decreto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Articulo 19. \u00a0 El Instituto \u00a0Nacional del Transporte, de oficio o a solicitud del Ministerio de Agricultura \u00a0o de cualquier otra autoridad, aplicar\u00e1 las sanciones pertinentes conforme a la \u00a0ley, a los transportadores que infrinjan las disposiciones del presente Decreto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 20. Ning\u00fan tripulante \u00a0nacional o extranjero podr\u00e1 embarcar az\u00facar en puerto colombiano para su \u00a0consumo. El az\u00facar que forme parte de \u00a0las provisiones de una nave, s\u00f3lo se podr\u00e1 embarcar a pedido del capit\u00e1n de \u00a0\u00e9sta o por intermedio de un agente mar\u00edtimo, en cantidades que no excedan de \u00a0dos kilos por tripulante. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Articulo 21. La Direcci\u00f3n General \u00a0de Aduanas coordinar\u00e1 con la polic\u00eda Nacional y otros organismos de Control y \u00a0seguridad, la instalaci\u00f3n y operaci\u00f3n de retienes y patrullas que hagan m\u00e1s \u00a0eficaz el cumplimiento de las normas del presente Decreto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 22. La omisi\u00f3n de \u00a0cualquiera de los requisitos se\u00f1alados en el presente Decreto, dar\u00e1 lugar al \u00a0decomiso del producto de las autoridades aduaneras o policivas, las cuales \u00a0pondr\u00e1n los cargamentos a orden del IDEMA dentro de las 24 horas siguientes, \u00a0para su distribuci\u00f3n al p\u00fablico. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Si existiere presunci\u00f3n de \u00a0contrabando, del hecho se dar\u00e1 traslado a las autoridades aduaneras para los \u00a0fines a que haya lugar y se les har\u00e1 entrega de los veh\u00edculos empleados. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El IDEMA pagar\u00e1 el precio del \u00a0az\u00facar a quien acredite la propiedad, despu\u00e9s de deducir un 10% por concepto de \u00a0gastos de comercializaci\u00f3n, salvo los casos en que se configure la presunci\u00f3n de \u00a0contrabando, en los cuales se \u00a0aplicar\u00e1n las normas del Estatuto Penal \u00a0Aduanero. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Articula 23. El presente Decreto rige a partir de la fecha de su \u00a0expedici\u00f3n y deroga todas las disposiciones que le sean contrarias. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Comun\u00edquese, Publ\u00edquese y \u00a0C\u00famplase. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Dado en Bogot\u00e1, D. E., a 15 de \u00a0enero de 1981. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">JULIO \u00a0CESAR TURBAY AYALA \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Justicia, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Felio Andrade Manrique. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de hacienda y Cr\u00e9dito P\u00fablico, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Jaime Garc\u00eda Parra. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de \u00a0Defensa Nacional, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Luis Carlos Camacho \u00a0Leyva, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Agricultura, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Gustavo \u00a0Dajer Chadid. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Desarrollo Econ\u00f3mico, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Andr\u00e9s Restrepo Londo\u00f1o. \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de \u00a0Obras P\u00fablicas y Transporte, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Enrique \u00a0Vargas Ram\u00edrez., \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Jefe del Departamento Administrativo de Seguridad, \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Manuel Guillermo Silva Gonz\u00e1lez.<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-15967","post","type-post","status-publish","format-standard","hentry","category-decretos-1981"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/15967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=15967"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/15967\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=15967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=15967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=15967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}