{"id":16023,"date":"2023-07-07T20:41:30","date_gmt":"2023-07-07T20:41:30","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-1040-de-1982\/"},"modified":"2023-07-07T20:41:30","modified_gmt":"2023-07-07T20:41:30","slug":"decreto-1040-de-1982","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-1040-de-1982\/","title":{"rendered":"DECRETO 1040 DE 1982"},"content":{"rendered":"\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETO 1040 \u00a0DE 1982 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(abril 15) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">por el \u00a0cual se establece una nota adicional en el Arancel de Aduanas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Presidente de la Rep\u00fablica de Colombia, en uso de sus \u00a0facultades legales y en especial de las que le confiere la \u00a0 Ley 6a de 1971 y previo \u00a0concepto del Consejo Nacional de Pol\u00edtica Aduanera, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETA: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 1\u00b0 Se establece como Nota Adicional en el Arancel \u00a0de Aduanas la siguiente: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Los bienes de capital, sus accesorios y repuestos \u00a0indispensables, para el establecimiento o ampliaci\u00f3n de industrias o \u00a0agroindustrias destinadas a la producci\u00f3n de bienes, en regiones que con \u00a0respecto al desarrollo general de la econom\u00eda nacional registren evidente \u00a0retraso, debido entre otros factores a su posici\u00f3n geogr\u00e1fica, bajo nivel de productividad, \u00a0de empleo o ingreso perc\u00e1pita, tendr\u00e1n una tarifa arancelaria del 1% \u00a0ad-valorem, siempre que previamente a su importaci\u00f3n y en cada caso el Consejo \u00a0Nacional de Pol\u00edtica Aduanera as\u00ed lo determine. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Para efectos del presente Decreto se consideran como zonas \u00a0que registran evidente retraso con respecto al desarrollo general de la \u00a0econom\u00eda nacional, el Departamento del Choc\u00f3, el Departamento de Nari\u00f1o con \u00a0excepci\u00f3n de la ciudad de Pasto, el Caquet\u00e1 y las Intendencias y Comisar\u00edas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Consejo Nacional de Pol\u00edtica Aduanera expedir\u00e1 con \u00a0destino a la Subdirecci\u00f3n T\u00e9cnica de la Direcci\u00f3n General de Aduanas dos (2) \u00a0copias de la Resoluci\u00f3n aprobatoria de la tarifa \u00fanica. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La Aduana aceptara en los manifiestos y documentos anexos, \u00a0las posiciones arancelarias declaradas en los registros o licencias de \u00a0importaci\u00f3n para las m\u00e1quinas y elementos aprobados por el Consejo Nacional de \u00a0Pol\u00edtica Aduanera siempre que correspondan a los enumerados en la \u00a0correspondiente resoluci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">En el caso de que los bienes no correspondan a los \u00a0declarados, la Aduana tomar\u00e1 las determinaciones que las disposiciones legales \u00a0establecen al respecto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Para conceder estas tarifas, el Consejo tendr\u00e1 en cuenta, \u00a0entre otros, los siguientes criterios: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Existencia o no de producci\u00f3n nacional. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Compromisos del Grupo Andino y de ateos procesos do \u00a0integraci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Grado de tecnolog\u00eda, y \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Efectos sobre el medio ambiente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La tarifa se aplicar\u00e1 a los equipos que autorice el \u00a0Consejo Nacional de Pol\u00edtica Aduanera antes del 31 de diciembre de 1982, aun \u00a0cuando lleguen al pa\u00eds con` posterioridad a la citada fecha. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 2\u00b0 El presente Decreto rige a partir c\u00ede la fecha \u00a0de su expedici\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Dado en Bogot\u00e1, D. E. a 15 de abril de 1982. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">JULIO CESAR TURBAY AYALA \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Hacienda y Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Eduardo \u00a0Wiesner Dur\u00e1n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 1040 \u00a0DE 1982 \u00a0 \u00a0 (abril 15) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 por el \u00a0cual se establece una nota adicional en el Arancel de Aduanas. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, en uso de sus \u00a0facultades legales y en especial de las que le confiere la \u00a0 Ley [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-16023","post","type-post","status-publish","format-standard","hentry","category-decretos-1982"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/16023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=16023"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/16023\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=16023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=16023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=16023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}