{"id":16323,"date":"2023-07-07T20:41:45","date_gmt":"2023-07-07T20:41:45","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-307-de-1982\/"},"modified":"2023-07-07T20:41:45","modified_gmt":"2023-07-07T20:41:45","slug":"decreto-307-de-1982","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-307-de-1982\/","title":{"rendered":"DECRETO 307 DE 1982"},"content":{"rendered":"\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETO 307 \u00a0DE 1982 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(febrero 4) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">por el \u00a0cual se dictan normas para el normal funcionamiento del Departamento del \u00a0Caquet\u00e1. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Presidente de la Rep\u00fablica de Colombia, en uso de las \u00a0facultades que le confiere el art\u00edculo 17 de la Ley 78 de 1981 y \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CONSTDERANDO : \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Que el art\u00edculo 17 de la Ley 78 de 1981 autoriza \u00a0al Presidente de la Rep\u00fablica para proveer acerca de las omisiones que se \u00a0presenten en desarrollo de la misma, con el objeto de lograr el normal \u00a0funcionamiento del Departamento del Caquet\u00e1. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Que el art\u00edculo 13 de la referida ley autoriza al Consejo \u00a0Intendencial del Caquet\u00e1 para que ejerza las atribuciones que el art\u00edculo 187, de la Constituci\u00f3n Pol\u00edtica \u00a0consagra para las asambleas departamentales. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Que es necesario reglamentar el funcionamiento del Consejo \u00a0Intendencial a partir del 1\u00ba de enero de 1982 y hasta cuando entre a ejercer \u00a0sus funciones la Asamblea del Departamento del Caquet\u00e1, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETA: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Articulo primero. El Consejo Intendencial del Caquet\u00e1 \u00a0deber\u00e1 ce\u00f1irse en el ejercicio de las funciones que le atribuye el art\u00edculo 13 \u00a0de la Ley 78 de 1981, a las \u00a0normas constitucionales y legales que rigen para las Asambleas Departamentales \u00a0en relaci\u00f3n con la presentaci\u00f3n y expedici\u00f3n de ordenanzas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo Segundo, Los actos administrativos que \u00a0expida el Consejo Intendencial recibir\u00e1n el nombre de Acuerdos Intendenciales \u00a0Especiales. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo tercero. Los Consejeros Intendenciales continuar\u00e1n \u00a0devengando los emolumentos y las Prestaciones Sociales que ven\u00edan disfrutando \u00a0como Consejeros Intendenciales, y continuar\u00e1 aplic\u00e1ndoseles las prohibiciones, \u00a0inhabilidades e incompatibilidades establecidas por la Constituci\u00f3n y las leyes \u00a0para Ios diputados, as\u00ed como el r\u00e9gimen de renuncias y excusas aplicables a \u00a0estos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo cuarto. El reglamento interno del Consejo \u00a0Intendencial del Caquet\u00e1 continuar\u00e1 aplic\u00e1ndose en cuanto no sea incompatible \u00a0con las nuevas atribuciones asignadas al Consejo, mientras la Asamblea dicta su \u00a0propio reglamento. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo quinto. Este Decreto rige a partir de la fecha de \u00a0su expedici\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Dado en Bogot\u00e1, a 4 de febrero de 1982. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">JULIO CESAR TURBAY AYALA \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Gobierno, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Jorge \u00a0Mario Eastman. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 307 \u00a0DE 1982 \u00a0 \u00a0 (febrero 4) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 por el \u00a0cual se dictan normas para el normal funcionamiento del Departamento del \u00a0Caquet\u00e1. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, en uso de las \u00a0facultades que le confiere el art\u00edculo 17 de la Ley 78 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-16323","post","type-post","status-publish","format-standard","hentry","category-decretos-1982"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/16323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=16323"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/16323\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=16323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=16323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=16323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}