{"id":16549,"date":"2023-07-07T21:29:05","date_gmt":"2023-07-07T21:29:05","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-2087-de-1983\/"},"modified":"2023-07-07T21:29:05","modified_gmt":"2023-07-07T21:29:05","slug":"decreto-2087-de-1983","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-2087-de-1983\/","title":{"rendered":"DECRETO 2087 DE 1983"},"content":{"rendered":"\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETO 2087 \u00a0DE 1983 <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(julio 22) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">por el cual se introducen unas modificaciones en el \u00a0Arancel de Aduanas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Presidente de la Rep\u00fablica de Colombia, en \u00a0ejercicio de las facultades que le confieren los art\u00edculos 120 ordinal 22, y \u00a0205 de la Constituci\u00f3n Nacional, en desarrollo de lo previsto en la \u00a0 Ley 6a de 1971 y o\u00eddo \u00a0el concepto del Consejo Nacional de Pol\u00edtica Aduanera, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETA: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 1\u00b0 Establ\u00e9cese la siguiente nota en los \u00a0cap\u00edtulos 39, 40, 73, 84, 85 y 90 del Arancel de Aduanas: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&#8220;Los productos de este Cap\u00edtulo que se \u00a0importen exclusivamente para la producci\u00f3n de abonos y fertilizantes, tendr\u00e1n \u00a0un grav\u00e1men ad-valorem del 1%. Para la aplicaci\u00f3n de este grav\u00e1men la Aduana \u00a0exigir\u00e1 en cada caso, una certificaci\u00f3n expedida por el INCOMEX sobre la no \u00a0existencia de producci\u00f3n nacional y el concepto favorable del Ministerio de \u00a0Agricultura&#8221;. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 2\u00ba. Establ\u00e9cese la siguiente nota en el \u00a0Cap\u00edtulo 51 del Arancel de Aduanas: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&#8220;Fijase en 20% el gravamen ad-valorem para los \u00a0hilados correspondientes a las posiciones y descripciones citadas a \u00a0continuaci\u00f3n y que sean importadas como insumo por la Industrias productoras \u00a0del sector textil: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Posici\u00f3n \u00a0\u00a0\u00a0\u00a0\u00a0Descripci\u00f3n \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">51.01.04.01 \u00a0\u00a0Hilados de Poliester liso, \u00a0te\u00f1ido en la masa. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">51.01.04.01 \u00a0\u00a0Hilados de poliester liso, \u00a0cati\u00f3nico. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">51.01.04.01 \u00a0\u00a0Hilados de poliester liso, \u00a0con un DPF igual o menor a 1.5. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">51.01.04.01 \u00a0\u00a0Hilados de poliester liso \u00a0de 40 denier o menos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">51.01.02.01 \u00a0\u00a0\u00a0Hilados de nylon antiest\u00e1tico trilobal brillante en 40 denier y de \u00a012 o \u00a0\u00a0\u00a0\u00a0\u00a0mas filamentos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">51.01.52.00 \u00a0\u00a0Hilados de triacetato con \u00a0un DPF igual o menor a 2.5. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&#8220;Para tener derecho a este grav\u00e1men, deber\u00e1n \u00a0presentar en el momento de la nacionalizacion, un concepto favorable del \u00a0Ministerio de Desarrollo Econ\u00f3mico&#8221;. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 3\u00ba. Establ\u00e9cense los siguientes grav\u00e1menes \u00a0ad-valorem para las posiciones de Arancel de Aduanas que a continuaci\u00f3n se \u00a0indican: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Posici\u00f3n \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Grav\u00e1men % \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">39.03.02.00 \u00a0\u00a0\u00a044 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">84.15.90.05 \u00a0\u00a0\u00a039 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 4\u00ba. Crease la siguiente posici\u00f3n en el \u00a0Arancel de Aduanas, con la descripci\u00f3n y grav\u00e1men ad-valorem que a continuaci\u00f3n \u00a0se indica: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Posici\u00f3n \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Descripci\u00f3n \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Grav\u00e1men \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">39.02.41.02 \u00a0\u00a0\u00a0Polipropileno biorientado en pel\u00edculas (rollos u hojas) \u00a0\u00a0\u00a0\u00a044 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 5\u00ba. El presente Decreto rige a partir de \u00a0la fecha de su expedici\u00f3n y se aplica a las mercanc\u00edas que se encuentren en \u00a0proceso de nacionalizaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Dado en Bogot\u00e1, D. E., a 22 de julio de 1983. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">BELISARIO BETANCUR \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Hacienda y Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Edgar \u00a0Guti\u00e9rrez Castro. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 2087 \u00a0DE 1983 (julio 22) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 por el cual se introducen unas modificaciones en el \u00a0Arancel de Aduanas. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, en \u00a0ejercicio de las facultades que le confieren los art\u00edculos 120 ordinal 22, y \u00a0205 de la Constituci\u00f3n Nacional, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-16549","post","type-post","status-publish","format-standard","hentry","category-decretos-1983"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/16549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=16549"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/16549\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=16549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=16549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=16549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}