{"id":16707,"date":"2023-07-07T21:29:13","date_gmt":"2023-07-07T21:29:13","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-3354-de-1983\/"},"modified":"2023-07-07T21:29:13","modified_gmt":"2023-07-07T21:29:13","slug":"decreto-3354-de-1983","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/07\/decreto-3354-de-1983\/","title":{"rendered":"DECRETO 3354 DE 1983"},"content":{"rendered":"\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETO 3354 \u00a0DE 1983 <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(diciembre 2) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">por el cual se aprueba una reforma a los estatutos de la Caja de \u00a0Cr\u00e9dito Agrario, Industrial y Minero. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Presidente de la Rep\u00fablica de Colombia, en ejercicio de sus atribuciones legales \u00a0y, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Que conforme al art\u00edculo 64 de los estatutos de la \u00a0Caja de Cr\u00e9dito Agrario, Industrial y Minero, aprobados por los Decretos n\u00fameros 301 de 1982 y \u00a0 2461 de 1983, la \u00a0Junta Directiva de la misma instituci\u00f3n ha procedido a modificar el art\u00edculo 32 \u00a0de sus estatutos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Que corresponde al Gobierno Nacional aprobar dicha \u00a0modificaci\u00f3n, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETA: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo primero. Aprobar el Acuerdo n\u00famero 433 del \u00a02 de noviembre de 1983 adoptado por la Junta Directiva de la Caja de Cr\u00e9dito \u00a0Agrario, Industrial y Minero, por el cual se reforma el art\u00edculo 32 de los \u00a0estatutos cuya modificaci\u00f3n fue debatida en dos sesiones realizadas en semanas \u00a0distintas y con los votos acorde de los miembros requeridos, seg\u00fan consta en \u00a0las actas n\u00fameros 1935 y 1954 de enero 18 y noviembre 2.de 1983, cuyo texto es \u00a0el siguiente: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00abACUERDO N\u00daMERO 443 DE 1983 <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(noviembre 2) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">por el cual se reforman los estatutos de la Caja de Cr\u00e9dito Agrario, \u00a0Industrial y Minero. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La Junta Directiva de la Caja de Cr\u00e9dito Agrario, \u00a0Industrial y Minero, en uso de sus facultades legales y estatutarias, y \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1\u00ba. Que el honorable Consejo de Estado; en virtud \u00a0de consulta formulada por el se\u00f1or Ministro de Agricultura, en concepto del 26 \u00a0de agosto de 1983 precis\u00f3, que la Caja de Cr\u00e9dito Agrario, Industrial y Minero, \u00a0como sociedad de econom\u00eda mixta en la que el Estado posee m\u00e1s del 90% de su \u00a0capital social, se rige por las disposiciones legales previstas para las \u00a0empresas industriales y comerciales del Estado y en tal virtud, en desarrollo \u00a0de lo dispuesto en el art\u00edculo 5\u00ba del \u00a0 Decreto ley 3135 \u00a0de 1968, las actividades de direcci\u00f3n y confianza, que se cumplan en tales \u00a0empresas sometidas a su r\u00e9gimen, deben ser desempe\u00f1adas por personas que tengan \u00a0la calidad de empleados p\u00fablicos, lo que se debe determinar en los estatutos de \u00a0la entidad. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2\u00ba. Que \u00a0existen en la Caja Agraria, otras actividades de direcci\u00f3n y confianza; \u00a0diferentes a las que corresponden al Gerente General, las que deben ser \u00a0desempe\u00f1adas por empleados p\u00fablicos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3\u00ba. Que conforme con lo previsto en el art\u00edculo 64 \u00a0de los estatutos de la Caja de Cr\u00e9dito Agrario, Industrial y Minero, aprobados \u00a0por el \u00a0 Decreto n\u00famero \u00a0302 de 1982, estos pueden ser reformados por acuerdo de la asamblea de \u00a0accionistas-Junta Directiva. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4\u00ba. Que la \u00a0asamblea de accionistas-Junta Directiva, aprob\u00f3 en primer debate la \u00a0&#8220;reforma de los estatutos en su art\u00edculo 32&#8221;, seg\u00fan consta en el Acta \u00a0n\u00famero 1935, correspondiente a la sesi\u00f3n del 13 de enero de 1983. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">ACUERDA: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo primero. Reformar el art\u00edculo 32 de los \u00a0estatutos de la Caja de Cr\u00e9dito Agrario, Industrial y Minero, el cual quedar\u00e1 \u00a0as\u00ed:, &#8220;Todas las personas que prestan sus servicios a la Caja son \u00a0trabajadores oficiales, y, por lo tanto estar\u00e1n sometidos al r\u00e9gimen legal vigente para los mismos, a excepci\u00f3n \u00a0del siguiente personal que tendr\u00e1 la calidad de empleado p\u00fablico, adem\u00e1s del \u00a0Gerente General, conforme al art\u00edculo 5\u00ba \u00a0del \u00a0 Decreto 3135 de 1968: \u00a0Subgerentes, Asistentes de Subgerencia, Directores de Departamento, Piloto I, Asistente de Gerencia General, Asesor de \u00a0Gerencia General, Asesores Especiales, Jefes de Unidad, Asistente de Unidad, \u00a0Secretario General, Secretario Privado de Gerencia General, Delegado Especial \u00a0Subgerencia de Cr\u00e9dito, Auditor General, Secretario Auditor\u00eda, Asistente \u00a0Auditor\u00eda General, Secretario Auxiliar, Gerentes regionales, zonales y locales, \u00a0Subgerente de sucursal, zonales, locales, y de provisi\u00f3n agr\u00edcola. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Lo anterior no implica desconocimiento de ning\u00fan \u00a0derecho adquirido. Por tanto, quienes \u00a0actualmente desempe\u00f1an los cargos se\u00f1alados en calidad de trabajadores \u00a0oficiales, conservar\u00e1n esa calidad. Los que se designen en propiedad en \u00a0cualquiera de los citados cargos a partir de la vigencia de este Acuerdo, estar\u00e1n sometidos al r\u00e9gimen de los \u00a0empleados p\u00fablicos. Adquirir\u00e1n la \u00a0misma calidad de empleados p\u00fablicos, quienes, teniendo actualmente la \u00a0condici\u00f3n de trabajadores oficiales por estar desempe\u00f1ando cualquiera de los \u00a0cargos citados en la instituci\u00f3n, decidan cambiar la naturaleza de su \u00a0vinculaci\u00f3n con la Caja. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo segundo. Este Acuerdo rige a partir de la \u00a0vigencia del Decreto que lo apruebe, modificando los estatutos de Ia entidad. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Dado en Bogot\u00e1, D. E., a los dos (2) d\u00edas del mes \u00a0de noviembre de mil novecientos ochenta y tres (1983). \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Presidente, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Secretario, &#8230;\u00bb. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo segundo. El presente Decreto rige a partir \u00a0de la fecha de su expedici\u00f3n y deroga las disposiciones que Ie sean contrarias. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Comun\u00edquese, publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Dado en Bogot\u00e1, D. E., a. 2 de diciembre de 1983. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">BELISARIO BETANCUR \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Agricultura, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Gustavo \u00a0Castro Guerrero. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 3354 \u00a0DE 1983 (diciembre 2) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 por el cual se aprueba una reforma a los estatutos de la Caja de \u00a0Cr\u00e9dito Agrario, Industrial y Minero. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, en ejercicio de sus atribuciones legales \u00a0y, \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 CONSIDERANDO: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-16707","post","type-post","status-publish","format-standard","hentry","category-decretos-1983"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/16707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=16707"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/16707\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=16707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=16707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=16707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}