{"id":18092,"date":"2023-07-10T16:43:14","date_gmt":"2023-07-10T16:43:14","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/10\/decreto-2451-de-1986\/"},"modified":"2023-07-10T16:43:14","modified_gmt":"2023-07-10T16:43:14","slug":"decreto-2451-de-1986","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/10\/decreto-2451-de-1986\/","title":{"rendered":"DECRETO 2451 DE 1986"},"content":{"rendered":"\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETO \u00a02451 DE 1986 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(julio 31) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Por el cual se reglamentan \u00a0parcialmente el C\u00f3digo de Comercio (Decreto ley 410 de \u00a01971) y el Decreto ley 2324 \u00a0de 1984, sobre Transporte Mar\u00edtimo y se dictan \u00a0otras disposiciones. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Nota 1: \u00a0Derogado por el Decreto 3111 de 1997, \u00a0art\u00edculo 79. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Nota 2: \u00a0Derogado parcialmente por el Decreto 1478 de 1992. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Nota 3: Modificado por el Decreto 501 de 1990, \u00a0por el Decreto 1423 de 1989 \u00a0y por el Decreto 143 de 1988. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Presidente de la Rep\u00fablica de Colombia, \u00a0en ejercicio de las facultades que le confiere el art\u00edculo 120, ordinal 3 de la \u00a0Constituci\u00f3n Pol\u00edtica, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETA: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 1. TRANSPORTE \u00a0MARITIMO PRIVADO. El servicio de transporte mar\u00edtimo privado, tanto de cabotaje \u00a0como internacional, se prestar\u00e1 exclusivamente con naves de propiedad del \u00a0armador autorizado, matriculadas en Colombia, las cuales podr\u00e1n transportar \u00a0carga general o carga a granel. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 2. SOLICITUD \u00a0PARA TRANSPORTE PRIVADO. Para operar como transportador mar\u00edtimo privado el \u00a0interesado deber\u00e1 elevar solicitud ante el Director General Mar\u00edtimo y \u00a0Portuario, indicando las caracter\u00edsticas t\u00e9cnicas de la nave que pretende adquirir, \u00a0la descripci\u00f3n detallada de la clase de mercader\u00edas que pretende transportar y \u00a0los vol\u00famenes que espera movilizar por mes y por a\u00f1o. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 3. CARGA A \u00a0TRANSPORTAR. El transportador mar\u00edtimo privado s\u00f3lo podr\u00e1 transportar su propia \u00a0carga y siempre que \u00e9sta guarde relaci\u00f3n directa con el giro ordinario de su \u00a0actividad industrial y adem\u00e1s la nave re\u00fana las condiciones de especialidad \u00a0para el transporte de la clase de carga de que se trate tambi\u00e9n podr\u00e1 \u00a0autorizarse el transporte de combustibles o derivados del petr\u00f3leo, aun cuando \u00a0el transportador no desarrolle la actividad industrial de transformaci\u00f3n o \u00a0refinaci\u00f3n de hidrocarburos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. DIMAR podr\u00e1 \u00a0autorizar excepcionalmente y caso por caso, a un transportador mar\u00edtimo privado \u00a0para: (i) movilizar carga propia que no sea del giro ordinario de su industria, \u00a0o (ii) movilizar mercader\u00eda de cabotaje o de exportaci\u00f3n de terceros, no sujeta \u00a0a reserva de carga, a cambio de un flete, siempre que no existiere \u00a0transportador p\u00fablico en disponibilidad y oportunidad para movilizarlas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 4. TRANSPORTE \u00a0DE CARGAS NO AUTORIZADAS. Si la Autoridad Mar\u00edtima de oficio o por queja de \u00a0cualquier interesado llegare a establecer que el transportador privado moviliz\u00f3 \u00a0carga no autorizada, el armador incurrir\u00e1 en violaci\u00f3n de normas de la marina \u00a0mercante y el usuario, si lo hubiere, en incumplimiento de las normas de \u00a0reserva de carga, o de marina mercante en caso de cabotaje. Si dentro de los \u00a0dos (2) a\u00f1os siguientes a la infracci\u00f3n el transportador reincidiere, la Autoridad \u00a0Mar\u00edtima le suspender\u00e1 la autorizaci\u00f3n de transporte privado por un per\u00edodo \u00a0efectivo no inferior a seis meses, sin perjuicio de que se le aplique las \u00a0sanciones de que trata el art\u00edculo 80 del Decreto 2324 de 1984. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 5. \u00a0ADJUDICACION DE RUTAS Y SERVICIOS. La informaci\u00f3n de que trata el art\u00edculo 160 \u00a0del Decreto 2324 de 1984, \u00a0deber\u00e1 suministrarse con el siguiente detalle por parte del interesado: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. PUERTOS ENTRE LOS \u00a0CUALES PRESTARA EL SERVICIO. Dentro del se\u00f1alamiento de los puertos entre los \u00a0cuales pretende prestar el servicio, el interesado distinguir\u00e1 entre puertos \u00a0regulares y puertos opcionales o alternos. Estos \u00faltimos deber\u00e1n estar siempre \u00a0localizados entre puertos regulares. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El interesado indicar\u00e1 \u00a0si para tal ruta desea que se aplique la reserva de carga, en cuyo caso \u00a0indicar\u00e1 el sector o sectores geogr\u00e1ficos para este efecto. Cuando el \u00a0interesado pretenda la aplicaci\u00f3n de la reserva de carga en un sector que \u00a0incluya uno o m\u00e1s pa\u00edses, est\u00e1 obligado a se\u00f1alar y servir como puerto regular \u00a0al menos un puerto de cada pa\u00eds. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. FRECUENCIAS. \u00a0Indicar\u00e1 la m\u00ednima frecuencia o periodicidad con que se obliga a servir cada \u00a0puerto regular y la forma en que prestar\u00e1 el servicio p\u00fablico de transporte \u00a0para los puertos opcionales que solicita, fijando el m\u00ednimo de tonelaje o de \u00a0valor de flete por el cual se obliga a tocar el puerto alterno. El m\u00ednimo que \u00a0indique lo obligar\u00e1 para efectos de prestar al servicio, mas no implica el \u00a0levantamiento de la Reserva de Carga para aquellos embarques de cantidades \u00a0inferiores a tales m\u00ednimos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. NAVES QUE OPERARAN \u00a0EN LA RUTA Y PLAN DE ADQUISICIONES: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Cuando el armador \u00a0posee naves de bandera colombiana, presentar\u00e1 una lista relacionando aquellas \u00a0de las que es titular de dominio, con indicaci\u00f3n del puerto y n\u00famero de \u00a0matr\u00edcula, clasificaci\u00f3n, tonelaje, especialidad y la lista de las rutas que \u00a0actualmente tiene adjudicadas. Ilustrar\u00e1 la forma como planea cumplir con la \u00a0regularidad de las rutas ya asignadas y con la frecuencia ofrecida para la ruta \u00a0en estudio, teniendo en cuenta el n\u00famero, velocidad operativa y capacidad de \u00a0las naves propias y la limitaci\u00f3n de que trata el art\u00edculo 156 del Decreto 2324 de 1984. \u00a0Si de este an\u00e1lisis resultare que con las naves propias y las fletadas no puede \u00a0servir adecuadamente las rutas adjudicadas y la ruta en estudio, deber\u00e1 \u00a0acompa\u00f1ar el plan de adquisiciones de que trata el literal siguiente; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Cuando el \u00a0interesado no dispone de naves de bandera colombiana para el servicio o ruta \u00a0que solicita, presentar\u00e1 el plan de adquisiciones, el cual debe contener: (i) \u00a0Estudio de factibilidad operativa de como proyecta servir la ruta o servicio \u00a0solicitado, conforme al literal anterior; y (ii) n\u00famero y descripci\u00f3n de los \u00a0buques que se propone adquirir y plazo m\u00e1ximo para tales adquisiciones, con \u00a0indicaci\u00f3n de sus caracter\u00edsticas, tonelajes, clasificaci\u00f3n y especialidad. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4. ESTUDIO DE CARGAS. \u00a0El interesado debe presentar un completo estudio o an\u00e1lisis de los vol\u00famenes de \u00a0carga de importaci\u00f3n y exportaci\u00f3n transportados entre los puertos extranjeros \u00a0y colombianos solicitados, relativo a los dos \u00faltimos a\u00f1os; explicar\u00e1 qu\u00e9 \u00a0porcentajes espera transportar, teniendo en cuenta las autorizaciones \u00a0concedidas a otros armadores nacionales y la capacidad transportadora de \u00e9stos, \u00a0justificando en lo posible las razones por las cuales espera tomar las cargas \u00a0anunciadas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 6. \u00a0CONDICIONES DE LA ASIGNACION DE RUTAS. La resoluci\u00f3n por medio de la cual se \u00a0asigna una ruta indicar\u00e1 los puertos regulares, los puertos opcionales y la \u00a0frecuencia o condiciones en que ser\u00e1n servidos. As\u00ed mismo determinar\u00e1 el sector \u00a0o sectores geogr\u00e1ficos a los cuales se les aplicar\u00e1 la reserva de carga, si \u00a0ello fuere procedente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La frecuencia se\u00f1alada \u00a0en la resoluci\u00f3n ser\u00e1 la m\u00ednima a que el armador queda obligado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 7. FRECUENCIAS \u00a0Y PUERTOS REGULARES. Cuando el armador interesado demuestre que por causas no \u00a0imputables a \u00e9l est\u00e1 en imposibilidad de seguir cumpliendo con la frecuencia \u00a0se\u00f1alada en la respectiva resoluci\u00f3n que le adjudic\u00f3 la ruta o con el toque de \u00a0alguno o algunos de los puertos regulares asignados, DIMAR podr\u00e1 variar la \u00a0frecuencia respectiva o suspender la obligaci\u00f3n de servir el o los puertos \u00a0regulares de que se trate. Tal modificaci\u00f3n o variaci\u00f3n no podr\u00e1 otorgarse por \u00a0un per\u00edodo superior a 6 meses, y si cumplido este plazo subsistieren los hechos \u00a0que originaron la petici\u00f3n, DIMAR deber\u00e1 modificar o cancelar la ruta \u00a0originalmente asignada. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Cumplido el plazo de \u00a0esta autorizaci\u00f3n especial o desaparecidas las causas que dieron lugar a la \u00a0solicitud, el armador est\u00e1 obligado a normalizar el servicio dentro de los 30 \u00a0d\u00edas siguientes en los t\u00e9rminos de la adjudicaci\u00f3n inicial, o de lo contrario \u00a0se aplicar\u00e1 lo establecido en el art\u00edculo siguiente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 8. \u00a0MODIFICACION O CANCELACION DE RUTAS Y SERVICIOS. La Direcci\u00f3n General Mar\u00edtima \u00a0y Portuaria, podr\u00e1 siguiendo el procedimiento del art\u00edculo 82 del Decreto 2324 de 1984 \u00a0determinar si una ruta o servicio asignado se ci\u00f1e o no a las condiciones \u00a0establecidas en la autorizaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Si de tal \u00a0investigaci\u00f3n administrativa se establece que en efecto no se ha prestado el \u00a0servicio, o que \u00e9ste no se ci\u00f1e a las condiciones establecidas en tal autorizaci\u00f3n, \u00a0la Autoridad Mar\u00edtima podr\u00e1 imponer la amonestaci\u00f3n, suspensi\u00f3n o multa de que \u00a0trata el art\u00edculo 80 del Decreto 2324 de 1984, \u00a0o habida cuenta de la gravedad de la falta o por reincidencia cancelar\u00e1 la ruta \u00a0o servicio conforme lo dispone el art\u00edculo 150 del Decreto 2324 de 1984. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. El armador \u00a0colombiano al que se le haya cancelado una ruta o servicio no podr\u00e1 solicitar \u00a0directamente, ni por interpuesta persona, la adjudicaci\u00f3n de la misma ruta o \u00a0servicio dentro de los doce (12) meses siguientes, contados desde la fecha en \u00a0que efectivamente se suspendi\u00f3 la prestaci\u00f3n del servicio o la vigencia de la \u00a0ruta. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 9. VIGENCIA \u00a0DE RUTAS Y SERVICIOS. Para los efectos de lo dispuesto en el par\u00e1grafo 1 del \u00a0art\u00edculo 161 del Decreto 2324 de 1984, \u00a0cualquier ruta o servicio que hubiere sido otorgado, o autorizado por la \u00a0Direcci\u00f3n General Mar\u00edtima y Portuaria con anterioridad a la vigencia del \u00a0mencionado Decreto continuar\u00e1 con la vigencia que se hubiere fijado en la \u00a0resoluci\u00f3n respectiva, o en su defecto con un plazo de un (1) a\u00f1o, contado a \u00a0partir de la vigencia del presente Decreto, pero requerir\u00e1 el armador de que se \u00a0trate, contar con nave de bandera colombiana o asimilada para ejercer los \u00a0derechos de tal ruta o servicio. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 10. PLAZO \u00a0PARA ADQUIRIR NAVES. Los armadores colombianos que en la actualidad tengan \u00a0rutas o servicios autorizados, pero que no dispongan de naves de bandera \u00a0colombiana de su propiedad del tipo y especialidad necesarios para atender \u00a0tales rutas o servicios, deber\u00e1n adquirir y matricular en Colombia, o tomar en \u00a0arrendamiento financiero conforme al presente Decreto, al menos una (1) nave \u00a0del tipo y especialidad requerido para la debida movilizaci\u00f3n de las cargas \u00a0autorizadas, dentro del a\u00f1o siguiente a la vigencia del presente Decreto. El \u00a0incumplimiento de esta disposici\u00f3n acarrea por este solo hecho la cancelaci\u00f3n \u00a0de la ruta o servicio autorizado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Hasta \u00a0cuando los armadores cumplan con el requisito de adquirir la nave del tipo y \u00a0especialidad adecuados, o de tomarla en arrendamiento financiero, el ejercicio \u00a0de los derechos de tales asignaciones de ruta o servicio les quedar\u00e1n suspendidos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 11. \u00a0PROHIBICION DE DECISIONES. Ninguna ruta o servicio de transporte mar\u00edtimo podr\u00e1 \u00a0ser objeto de cesi\u00f3n total, ni parcial. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 12. Modificado por el Decreto 1423 de 1989, \u00a0art\u00edculo 39. PERMISO \u00a0DE ADQUISICI\u00d3N DE NAVES. La solicitud de adquisici\u00f3n de naves destinadas al \u00a0transporte mar\u00edtimo internacional o de cabotaje no ser\u00e1 tramitada hasta tanto \u00a0el solicitante haya obtenido la asignaci\u00f3n de ruta o servicio respectivo, a \u00a0menos que ya tenga ruta o servicio asignado, caso en el cual indicar\u00e1 su \u00a0destinaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Texto inicial: \u201cPERMISO DE INVERSION \u00a0EN NAVES. La solicitud de inversi\u00f3n en naves destinadas al transporte mar\u00edtimo \u00a0internacional o de cabotaje no ser\u00e1 tramitada hasta tanto el solicitante haya \u00a0obtenido la asignaci\u00f3n de la ruta o servicio respectivo, salvo que la presente \u00a0simult\u00e1neamente con la solicitud de ruta o servicio o se indique a qu\u00e9 ruta o \u00a0servicio ya adjudicado se destinar\u00e1n.\u201d. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 13. INFORME \u00a0SOBRE SERVICIOS PRESTADOS. Los informes de que trata el art\u00edculo 153 del Decreto 2324 de 1984, \u00a0deber\u00e1n presentarse a m\u00e1s tardar el 15 de febrero y el 15 de agosto de cada a\u00f1o \u00a0calendario, en los formatos que para tal fin elabore DIMAR. Los armadores \u00a0extranjeros podr\u00e1n presentar tales informes por conducto de sus agentes \u00a0mar\u00edtimos en Colombia. Dicho informe indicar\u00e1 adem\u00e1s la forma como el armador \u00a0colombiano cumpli\u00f3 con la frecuencia a que est\u00e1 obligado, seg\u00fan las rutas \u00a0asignadas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo transitorio. \u00a0Para el presente a\u00f1o el informe de que trata este art\u00edculo deber\u00e1 presentarse a \u00a0m\u00e1s tardar el 16 de febrero de 1987. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 14. REGISTRO \u00a0DE TRANSPORTADORES MARITIMOS. La resoluci\u00f3n que autorice a una persona natural \u00a0o jur\u00eddica para prestar servicio de transporte mar\u00edtimo p\u00fablico o privado, \u00a0ordenar\u00e1 su inscripci\u00f3n en el libro de registro como transportador mar\u00edtimo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Si el transportador no \u00a0posee naves de su propiedad para prestar el servicio el registro ser\u00e1 \u00a0provisional, hasta cuando adquiera una nave de bandera colombiana, en cuyo caso \u00a0el registro se tornar\u00e1 definitivo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Ning\u00fan registro \u00a0provisional podr\u00e1 tener una validez superior a nueve (9) meses. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Los \u00a0armadores colombianos que actualmente prestan servicio de transporte mar\u00edtimo \u00a0p\u00fablico o privado, a fin de inscribirse en el registro de transportadores \u00a0mar\u00edtimos, deber\u00e1n dentro de los tres (3) meses siguientes a la vigencia del \u00a0presente Decreto, presentar la solicitud correspondiente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 15. \u00a0EXPEDICION DEL CERTIFICADO DE TRANSPORTADOR MARITIMO. Ordenada la inscripci\u00f3n \u00a0por la Autoridad Mar\u00edtima, \u00e9sta a costa del interesado, le expedir\u00e1 el \u00a0certificado correspondiente que contendr\u00e1 los siguientes datos: (i) nombre o \u00a0raz\u00f3n social y domicilio del transportador; (ii) clase y especialidad de \u00a0servicio que tiene autorizado; (iii) ruta o servicio asignados. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. En los \u00a0certificados de registro provisional se indicar\u00e1 dicha condici\u00f3n y el t\u00e9rmino \u00a0de su vigencia. Los certificados se renovar\u00e1n cada dos (2) a\u00f1os, o cada vez que \u00a0se modifiquen las rutas o servicios. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 16. \u00a0CANCELACION DEL REGISTRO. La p\u00e9rdida de todas las rutas o servicios asignados \u00a0conllevar\u00e1 por ese solo hecho la cancelaci\u00f3n del registro como transportador \u00a0mar\u00edtimo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 17. SOLICITUD \u00a0DE APROBACION DE CONVENIOS DE TRANSPORTE MARITIMO O DE ASOCIACION. La solicitud \u00a0de aprobaci\u00f3n de los convenios a que se refieren los art\u00edculos 147 y 148 del Decreto 2324 de 1984, \u00a0ser\u00e1 presentada por el armador o armadores colombianos que lo hayan suscrito \u00a0dentro de los treinta (30) d\u00edas siguientes a su celebraci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La solicitud debe \u00a0contener la informaci\u00f3n y documentaci\u00f3n siguiente: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Raz\u00f3n social y \u00a0domicilio de la empresa o empresas navieras asociadas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Frecuencia del \u00a0servicio y el nombre de los puertos colombianos y extranjeros que se \u00a0comprometen a servir los armadores asociados. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Caracter\u00edsticas de \u00a0las naves que destinar\u00e1n los asociados para este servicio. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4. Nombre o raz\u00f3n \u00a0social y domicilios del representante o agente mar\u00edtimo del asociado extranjero \u00a0en el pa\u00eds. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">5. Conferencias \u00a0mar\u00edtimas a las cuales pertenecen los asociados en tr\u00e1ficos con Colombia. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">6. Copia con firmas \u00a0autenticadas del convenio y su traducci\u00f3n al espa\u00f1ol. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">7. Certificaci\u00f3n \u00a0aut\u00e9ntica de la autorizaci\u00f3n de ruta o servicio concedida al asociado extranjero \u00a0por la autoridad mar\u00edtima de su pa\u00eds, o su equivalente, si la hubiere. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">8. Formato del \u00a0conocimiento de embarque que utilizara el armador extranjero y su \u00a0correspondiente traducci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 18. \u00a0RECIPROCIDAD DE LOS CONVENIOS. A efecto de garantizar el cumplimiento de las \u00a0condiciones de reciprocidad e igualdad de tratamiento de que trata el art\u00edculo \u00a0148 del Decreto 2324 de 1984, \u00a0los convenios de transporte mar\u00edtimo o de asociaci\u00f3n deben contener al menos \u00a0las siguientes estipulaciones: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Compromiso del \u00a0armador extranjero de cobrar los mismos fletes o precios del transporte \u00a0mar\u00edtimo que sean registrados o autorizados para el armador colombiano o para \u00a0la Conferencia Mar\u00edtima de que se trate. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Manifestaci\u00f3n de \u00a0que el armador extranjero garantiza al colombiano las mismas facilidades de \u00a0acceso que \u00e9l tiene al mercado naviero en su pa\u00eds, y que en caso de ser \u00a0favorecido con carga proveniente de contratos de empr\u00e9stito o de financiaci\u00f3n \u00a0que suscriban el Gobierno de Colombia o los particulares, con el Gobierno o \u00a0entidades de su pa\u00eds o con organismos financieros internacionales, se obliga \u00a0\u00e9ste para con el armador colombiano a otorgarle una adecuada participaci\u00f3n en \u00a0el transporte de tal carga. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Compromiso del \u00a0armador extranjero de someter a la aprobaci\u00f3n o registro de su gobierno, o de \u00a0su autoridad mar\u00edtima, el convenio concertado, si estos fueren necesarios en su \u00a0pa\u00eds para la efectividad de tales compromisos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 19. CAUSALES \u00a0DE CANCELACION DE LA APROBACION DE LOS CONVENIOS. La Direcci\u00f3n General Mar\u00edtima \u00a0y Portuaria podr\u00e1 cancelar la aprobaci\u00f3n concedida cuando se presente una de \u00a0las siguientes circunstancias: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Se incumplan las \u00a0condiciones establecidas en el art\u00edculo 148 del Decreto 2324 de 1984. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Los servicios no se \u00a0presten en las condiciones y t\u00e9rminos establecidos en la respectiva resoluci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Pasados tres (3) \u00a0meses no se haya obtenido la aprobaci\u00f3n o registro del convenio por parte del \u00a0Gobierno o de la autoridad mar\u00edtima del pa\u00eds del asociado extranjero, si fuere \u00a0procedente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 20. TERMINO \u00a0DE LA AUTORIZACION DE LOS CONVENIOS. La aprobaci\u00f3n de los convenios de \u00a0asociaci\u00f3n o de transporte mar\u00edtimo s\u00f3lo surtir\u00e1 efectos legales hasta por un t\u00e9rmino \u00a0de dos (2) a\u00f1os, contados a partir de la ejecutoria de la respectiva \u00a0providencia. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 21. PERDIDA \u00a0DEL BENEFICIO DE LA RESERVA DE CARGA. Vencido el plazo de una ruta o servicio \u00a0asignado a un armador colombiano o cuando \u00e9ste sea suspendido o cancelado, los \u00a0armadores extranjeros asociados perder\u00e1n por este s\u00f3lo hecho el beneficio de la \u00a0reserva de carga para tal ruta o servicio. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 22. NAVES \u00a0ASIMILADAS PARA EFECTOS DE CONVENIOS. Se entender\u00e1n por naves de bandera \u00a0colombiana para los efectos del art\u00edculo 148 del Decreto 2324 de 1984, \u00a0no s\u00f3lo las que est\u00e9n matriculadas en Colombia, sino tambi\u00e9n todas las naves asimiladas \u00a0a buques de bandera colombiana para efectos de la reserva de carga, como se \u00a0dispone en el art\u00edculo 54 siguiente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 23. NAVES DE \u00a0LINEA REGULAR. Todas las naves de carga general que sean operadas por un \u00a0armador al cual la Direcci\u00f3n General Mar\u00edtima y Portuaria le haya asignado una \u00a0ruta internacional, ser\u00e1n consideradas para todos los efectos como naves de \u00a0l\u00ednea regular, no obstante que el armador autorizado no pertenezca a una \u00a0Conferencia Mar\u00edtima. Este beneficio se har\u00e1 extensivo a los armadores \u00a0asociados, siempre que los armadores colombianos manifiesten que reciben \u00a0tratamiento rec\u00edproco. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Las naves \u00a0graneleras de bandera colombiana con servicios autorizados por DIMAR se \u00a0asimilan, para todos los efectos portuarios y de servicios a la carga, a naves \u00a0de l\u00ednea regular. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 24. FLETE O \u00a0TARIFA. Para los efectos del Decreto 2324 de 1984, \u00a0se entiende como flete o precio del transporte mar\u00edtimo la denominada \u00a0&#8220;tarifa b\u00e1sica&#8221;, aumentada con los recargos o cualquier otro \u00a0componente que altere el valor final del transporte. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Las tarifas \u00a0deber\u00e1n agruparse por ruta o por sector geogr\u00e1fico, pudiendo diferenciarse \u00a0seg\u00fan los distintos puertos de origen y destino, y deber\u00e1n fijarse por \u00a0categor\u00edas de cargamentos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 25. REGISTRO \u00a0DE TARIFAS BASICAS DE CONFERENCIA. Los armadores colombianos que hayan sido \u00a0autorizados para ingresar a Conferencias Mar\u00edtimas, deber\u00e1n registrar las \u00a0tarifas b\u00e1sicas para carga general aprobadas por dicha Conferencia y aplicables \u00a0para los tr\u00e1ficos con Colombia, al menos con treinta (30) d\u00edas de antelaci\u00f3n a \u00a0la fecha \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">en que tales tarifas \u00a0b\u00e1sicas vayan a ser aplicadas. A fin de que puedan ser registradas estas \u00a0tarifas b\u00e1sicas por la Autoridad Mar\u00edtima, la solicitud deber\u00e1 suscribirla el \u00a0armador colombiano interesado y el representante de la respectiva Conferencia \u00a0Mar\u00edtima registrado ante DIMAR. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a026. Modificado por el Decreto 501 de 1990, \u00a0art\u00edculo 23. RECARGOS EN \u00a0FLETES. En ejercicio de las funciones y atribuciones que le fija el numeral 17 \u00a0del art\u00edculo 5o. del Decreto 2324 de 1984, los recargos o componentes que \u00a0incrementen el precio del transporte mar\u00edtimo y que pretendan cobrar los \u00a0armadores miembros o asociados a una conferencia mar\u00edtima, deber\u00e1n ser \u00a0previamente sometidos a consideraci\u00f3n de la Direcci\u00f3n General Mar\u00edtima y \u00a0Portuaria para que \u00e9sta los autorice, si los encuentra suficientemente \u00a0justificados y su cuant\u00eda acorde con la circunstancia o hecho que les da \u00a0origen. Para este efecto, el representante registrado de la conferencia \u00a0mar\u00edtima deber\u00e1 presentar la correspondiente solicitud con explicaci\u00f3n clara, \u00a0completa y justificada de cada uno de los recargos o costos que de una u otra \u00a0forma finalmente se cobren al usuario en adici\u00f3n a la &#8220;tarifa b\u00e1sica&#8221; \u00a0registrada. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La \u00a0Direcci\u00f3n General Mar\u00edtima y Portuaria deber\u00e1 resolver la petici\u00f3n dentro de \u00a0los quince (15) d\u00edas siguientes, contados a partir de la fecha de su \u00a0presentaci\u00f3n, si \u00e9sta re\u00fane los requisitos antes se\u00f1alados. Cuando se trate de \u00a0recargos motivados en aspectos portuarios, la petici\u00f3n se resolver\u00e1 dentro de los \u00a0treinta (30) d\u00edas siguientes a su presentaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Texto anterior: Modificado \u00a0por el Decreto 143 de 1988, \u00a0art\u00edculo 21. \u201cRECARGOS EN FLETES. En ejercicio de las funciones y atribuciones que le fija el numeral 17 del \u00a0art\u00edculo 5\u00ba del Decreto 2324 de 1984, \u00a0los recargos o componentes que incrementen el \u00a0precio del transporte mar\u00edtimo y que pretendan cobrar los armadores miembros o \u00a0asociados a una Conferencia Mar\u00edtima, deber\u00e1n ser previamente sometidos a \u00a0consideraci\u00f3n de la Direcci\u00f3n General Mar\u00edtima y Portuaria para que \u00e9sta los \u00a0autorice, si los encuentra suficientemente justificados y su cuant\u00eda acorde con \u00a0la circunstancia o hecho que les da origen. Para este efecto, el representante \u00a0registrado de la Conferencia Mar\u00edtima deber\u00e1 presentar la correspondiente \u00a0solicitud con explicaci\u00f3n clara, completa y justificada de cada. uno de los \u00a0recargos o costos que de una u otra forma finalmente se cobren al usuario en \u00a0adici\u00f3n a la &#8220;tarifa b\u00e1sica&#8221; registrada. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La Direcci\u00f3n General Mar\u00edtima y Portuaria \u00a0deber\u00e1 resolver la petici\u00f3n dentro de los quince (15) d\u00edas siguientes, contados \u00a0a partir de la fecha de su presentaci\u00f3n, si \u00c9sta re\u00fane los requisitos antes \u00a0se\u00f1alados. Cuando se trate de recargos motivados en aspectos portuarios, la \u00a0petici\u00f3n se resolvera dentro de los treinta (30) d\u00edas siguientes a su \u00a0presentaci\u00f3n.\u201d. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Texto inicial del art\u00edculo \u00a026.: \u201cRECARGOS \u00a0EN FLETES O TARIFAS DE CONFERENCIA. En ejercicio de las funciones y \u00a0atribuciones que le fija el numeral 17 del art\u00edculo 5 del Decreto 2324 de 1984, \u00a0los recargos o componentes que incrementen el \u00a0precio del transporte mar\u00edtimo y que pretendan cobrar los armadores miembros o \u00a0asociados a una Conferencia Mar\u00edtima, deber\u00e1n ser previamente sometidos a \u00a0consideraci\u00f3n de la Direcci\u00f3n General Mar\u00edtima y Portuaria para que \u00e9sta los \u00a0autorice, si los encuentra suficientemente justificados y su cuant\u00eda acorde con \u00a0la circunstancia o hecho que les da origen. Para este efecto, el representante \u00a0registrado de la Conferencia Mar\u00edtima, deber\u00e1 presentar la correspondiente \u00a0solicitud con explicaci\u00f3n clara, completa y justificada de cada uno de los \u00a0recargos o costos que de una u otra forma finalmente se cobren al usuario, en \u00a0adici\u00f3n a la &#8220;tarifa b\u00e1sica&#8221; registrada. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La Direcci\u00f3n \u00a0General Mar\u00edtima y Portuaria deber\u00e1 resolver la petici\u00f3n a m\u00e1s tardar dentro de \u00a0los treinta (30) d\u00edas siguientes, contados a partir de cuando la petici\u00f3n est\u00e9 \u00a0completa. El incumplimiento de este t\u00e9rmino ser\u00e1 causal de mala conducta.\u201d. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 27. Modificado por el Decreto 501 de 1990, \u00a0art\u00edculo 30. REGISTRO O AUTORIZACION DE TARIFAS A FLETES. \u00a0Todo transportador mar\u00edtimo de carga general, sea internacional o de cabotaje y \u00a0que no re\u00fana las condiciones del art\u00edculo 25 de este Decreto, est\u00e1 obligado a \u00a0presentar para aprobaci\u00f3n de la Direcci\u00f3n General Mar\u00edtima y Portuaria las \u00a0tarifas b\u00e1sicas, con sus recargos o cualquier otro componente que altere el \u00a0valor final del transporte, con explicaci\u00f3n clara y completa de los mismos, si \u00a0tales tarifas fueren superiores a las registradas por la conferencia mar\u00edtima para \u00a0dicho tr\u00e1fico, o si no hubiere tarifas de conferencia. De lo contrario, deber\u00e1 \u00a0presentarlas tan s\u00f3lo para su registro. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Texto inicial: \u201cAUTORIZACION DE \u00a0TARIFAS O FLETES. Todo transportador mar\u00edtimo de carga general, sea \u00a0internacional o de cabotaje, y que no re\u00fana las condiciones del art\u00edculo 25 de \u00a0este Decreto, est\u00e1 obligado a presentar para su registro y aprobaci\u00f3n a la \u00a0Direcci\u00f3n General Mar\u00edtima y Portuaria las tarifas b\u00e1sicas, con sus recargos o \u00a0cualquier otro componente que altere el valor final del transporte, con \u00a0explicaci\u00f3n clara y completa de los mismos.\u201d. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 28. REVISION \u00a0DE TARIFAS O FLETES. En cualquier momento el armador interesado o el \u00a0representante de la Conferencia Mar\u00edtima de que se trate, podr\u00e1 pedir revisi\u00f3n o \u00a0modificaci\u00f3n parcial o total de las tarifas o fletes registrados o autorizados. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 29. \u00a0SUSPENSION DE TARIFA BASICA POR AUTORIDAD. La autorizaci\u00f3n o registro que la \u00a0Direcci\u00f3n General Mar\u00edtima y Portuaria otorga a las tarifas b\u00e1sicas no obsta \u00a0para que posteriormente pueda pedir explicaciones o justificaciones sobre \u00a0cualquiera de \u00e9stas, e inclusive suspender la vigencia de la tarifa para uno o \u00a0varios productos, si las circunstancias as\u00ed lo ameritan. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 30. SUSPENSION O REDUCCION DE \u00a0RECARGOS POR AUTORIDAD. En cualquier momento la Direcci\u00f3n General Mar\u00edtima y \u00a0Portuaria podr\u00e1 disminuir o suspender la aplicaci\u00f3n o cobro de cualquiera de \u00a0las variaciones o recargos a la tarifa b\u00e1sica, si las razones que sirvieron de \u00a0justificaci\u00f3n para aprobarlos ya no est\u00e1n vigentes, o estas circunstancias se \u00a0han modificado sustancialmente. Para este efecto deber\u00e1 o\u00edr previamente, bien \u00a0al armador interesado o al representante acreditado de la Conferencia Mar\u00edtima \u00a0de que se trate. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 31. REBAJAS \u00a0DE TARIFAS O SUSPENSION DE RECARGOS POR LOS ARMADORES. En cualquier momento \u00a0podr\u00e1 el armador interesado o el representante de la Conferencia Mar\u00edtima \u00a0comunicar a DIMAR que ha disminuido o suspendido los recargos que ten\u00eda \u00a0autorizados. Tambi\u00e9n podr\u00e1 comunicar la disminuci\u00f3n en cualquiera de las \u00a0tarifas, siempre que sea de car\u00e1cter general para todos los usuarios, bien \u00a0cuando se refiera a un producto espec\u00edfico con fines de promoci\u00f3n o cuando se \u00a0cumplan ciertas condiciones particulares especiales, como por ejemplo: por volumen \u00a0a transportar, por facilidades en el manipuleo de la carga o semejantes. La \u00a0disminuci\u00f3n podr\u00e1 ser para un s\u00f3lo usuario, siempre que sea por un per\u00edodo \u00a0determinado y para carga de un proyecto especial. Estas variaciones tendr\u00e1n \u00a0aplicaci\u00f3n a partir del d\u00eda siguiente a aqu\u00e9l en que se reciba por la Direcci\u00f3n \u00a0General Mar\u00edtima y Portuaria la comunicaci\u00f3n en que se le informa de la \u00a0disminuci\u00f3n del precio del transporte mar\u00edtimo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Las tarifas \u00a0de car\u00e1cter general as\u00ed rebajadas, no podr\u00e1n elevarse, sino mediante el \u00a0cumplimiento de lo establecido en los art\u00edculos 25, 26 y 27 de este Decreto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 32. FLETES NO \u00a0SUJETOS A REGISTRO NI APROBACION. El flete o precio del transporte de aquellas \u00a0mercader\u00edas que no est\u00e9n sujetas a reserva de carga no estar\u00e1n tampoco sujetas \u00a0a registro, ni aprobaci\u00f3n de DIMAR; tampoco lo estar\u00e1n los fletes o precio del \u00a0transporte para cargas a granel. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 33. COBRO \u00a0INDEBIDO DE FLETES O TARIFAS. DIMAR deber\u00e1 imponer las sanciones de que trata \u00a0el art\u00edculo 80 del Decreto 2324 de 1984, \u00a0cuando establezca que: (i) los armadores nacionales o extranjeros asociados, \u00a0conferenciados, cobren tarifas b\u00e1sicas de conferencia que no hayan sido \u00a0previamente registradas; o (ii) los armadores colombianos o extranjeros \u00a0asociados, no conferenciados, cobren tarifas b\u00e1sicas no autorizadas previamente \u00a0por DIMAR; o (iii) cuando armadores nacionales o extranjeros asociados, \u00a0pertenecientes o no a una Conferencia Mar\u00edtima, cobren recargos o componentes \u00a0que conlleven un mayor valor del precio final del transporte, sin que medie la \u00a0previa autorizaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Adicionalmente a las \u00a0sanciones administrativas anteriores, tendr\u00e1n derecho los usuarios para repetir \u00a0contra tales armadores colombianos o extranjeros por lo pagado en exceso al \u00a0precio del transporte registrado o autorizado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 34. \u00a0COMPETENCIA DESLEAL. Ning\u00fan transportador p\u00fablico o privado, en forma directa o \u00a0por interpuesta persona, de manera individual o en conjunto con cualesquiera \u00a0otras personas, podr\u00e1 efectuar actos o utilizar medios o sistemas que afecten \u00a0el desarrollo leal y ordenado de los servicios de transporte mar\u00edtimo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Se consideran, entre \u00a0otros, como medios o sistemas encausados a obtener la desviaci\u00f3n indebida de la \u00a0clientela o de los usuarios, y por lo tanto contrarios a la costumbre mercantil \u00a0y a las normas de marina mercante los siguientes: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Cobrar o recibir \u00a0por el transporte de mercader\u00edas o por otros servicios conexos con dicho \u00a0transporte, compensaci\u00f3n mayor, menor o diferente a las tarifas o fletes \u00a0registrados o autorizados por la Autoridad Mar\u00edtima Nacional. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Ofrecer o efectuar \u00a0reembolsos o descuentos que de cualquier manera disminuyan los fletes o tarifas \u00a0registrados o autorizados. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Tolerar o promover \u00a0que cualquier persona efect\u00fae transporte de mercader\u00edas con tarifas distintas a \u00a0las que correspondan al bien efectivamente transportado o sin aplicar los \u00a0recargos autorizados o registrados mediante cualquier procedimiento, tales como \u00a0sub-facturaci\u00f3n, clasificaci\u00f3n indebida de las mercanc\u00edas, o suplantaci\u00f3n de la \u00a0categor\u00eda del cargamento, pesos o medidas contrarias a la verdad, o pr\u00e1cticas semejantes. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4. Cobrar o exigir \u00a0cualquier tipo de compensaci\u00f3n por la expedici\u00f3n de certificaciones sobre \u00a0disponibilidad de naves o capacidad transportadora. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">5. Lucrarse en forma \u00a0directa o indirecta por extender los derechos de protecci\u00f3n de bandera \u00a0colombiana a naves extranjeras cuando el armador colombiano realmente no \u00a0efect\u00fae la solicitaci\u00f3n de la carga o la consecuci\u00f3n de la nave a fletar. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">6. En general \u00a0cualquier pr\u00e1ctica que sea discriminatoria y perjudicial para con los usuarios \u00a0del transporte mar\u00edtimo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Estas conductas o \u00a0pr\u00e1cticas desleales dar\u00e1n lugar a la aplicaci\u00f3n de las sanciones de que trata \u00a0el art\u00edculo 80 del Decreto 2324 de 1984, \u00a0sin perjuicio de las dem\u00e1s sanciones o acciones con origen en las pr\u00e1cticas \u00a0comerciales restrictivas o de competencia desleal. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 35. VIGENCIA \u00a0INICIAL DE TARIFAS. Las tarifas o fletes que con anterioridad a la expedici\u00f3n \u00a0del presente decreto, hubieren sido presentados a DIMAR por armadores \u00a0colombianos conferenciados o no, se consideran registrados o autorizados por \u00a0ese solo hecho, conforme los t\u00e9rminos del presente Decreto. Aquellos armadores \u00a0que a partir de la vigencia del presente Decreto no tengan las tarifas \u00a0registradas o autorizadas para sus respectivas rutas, tendr\u00e1n un plazo de tres \u00a0(3) meses, contados a partir de la vigencia del mismo para cumplir con los \u00a0tr\u00e1mites legales que aqu\u00ed se establecen. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 36. APROBACION \u00a0DE INGRESO A CONFERENCIAS MARITIMAS. La Direcci\u00f3n General Mar\u00edtima y Portuaria \u00a0aprobar\u00e1 el ingreso de los armadores colombianos a Conferencias Mar\u00edtimas \u00a0cuando considere que tal ingreso tiene por fin defender la estabilidad de un \u00a0sector b\u00e1sico para la producci\u00f3n de bienes y para la prestaci\u00f3n de un servicio \u00a0de inter\u00e9s para la econom\u00eda general, como son el transporte y el comercio \u00a0exterior colombiano. El armador colombiano interesado deber\u00e1 justificar su \u00a0solicitud y acompa\u00f1ar\u00e1 copia de los reglamentos de tal Conferencia. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La Conferencia \u00a0Mar\u00edtima dentro de tres (3) meses siguientes a que se le otorgue la \u00a0autorizaci\u00f3n de ingreso al armador colombiano deber\u00e1 acreditar su representante \u00a0en Colombia y registrar sus reglamentos, tarifas o fletes. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Los \u00a0armadores colombianos que celebren acuerdos o convenios que no puedan \u00a0considerarse como de Conferencia Mar\u00edtima, deber\u00e1n someter a autorizaci\u00f3n \u00a0previa de la Direcci\u00f3n General Mar\u00edtima y Portuaria las tarifas o fletes que \u00a0pretendan cobrar, conforme al art\u00edculo 27 del presente Decreto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 37. \u00a0REPRESENTACION DE LAS CONFERENCIAS MARITIMAS. Los armadores colombianos que a \u00a0la fecha de la expedici\u00f3n del presente Decreto sean miembros de una Conferencia \u00a0Mar\u00edtima por ese solo hecho se reputan autorizados para ello. Sin embargo, \u00a0deben procurar que dentro de los tres (3) meses siguientes a la vigencia del \u00a0presente Decreto, la respectiva Conferencia Mar\u00edtima acredite ante DIMAR la \u00a0persona que la representar\u00e1. Simult\u00e1neamente con el registro del representante \u00a0deber\u00e1 acompa\u00f1arse una copia de los reglamentos y tarifas vigentes de la \u00a0respectiva Conferencia, si \u00e9stos no reposaren ya en DIMAR. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. La \u00a0Conferencia Mar\u00edtima que dentro del plazo anterior no diere cumplimiento a lo \u00a0aqu\u00ed dispuesto, se entender\u00e1 que no tiene inter\u00e9s de actuar como Conferencia \u00a0Mar\u00edtima en cuanto a la autoridad colombiana, y en consecuencia sus tarifas \u00a0b\u00e1sicas, recargos y dem\u00e1s componentes de las tarifas o fletes quedar\u00e1n sujetos \u00a0al tr\u00e1mite el art\u00edculo 27 y concordantes del presente Decreto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 38. TIPOS DE \u00a0BUQUES. El tipo de buque a que se refiere el par\u00e1grafo del art\u00edculo 156 del Decreto 2324 de 1984, \u00a0hace relaci\u00f3n a su dise\u00f1o o habilitaci\u00f3n t\u00e9cnica para el transporte de carga, o \u00a0de pasajeros. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 39. \u00a0ESPECIALIDAD DE LOS BUQUES. La especialidad a la que se refieren los art\u00edculos \u00a0145 y 156 del Decreto 2324 de 1984 \u00a0hace relaci\u00f3n a la aptitud que debe poseer una nave carguera, por dise\u00f1o, transformaci\u00f3n \u00a0o adaptaci\u00f3n para transportar carga general, carga a granel seca o carga a \u00a0granel l\u00edquida. Esta especialidad se determinar\u00e1 de conformidad con los \u00a0certificados expedidos por la sociedad clasificadora que haya inspeccionado la \u00a0nave. Para las naves de transporte mar\u00edtimo de cabotaje inferiores a un mil \u00a0doscientas (1.200) toneladas de arqueo bruto, podr\u00e1 determinarse su \u00a0especialidad por medio de inspectores de la Direcci\u00f3n General Mar\u00edtima y \u00a0Portuaria; pero las destinadas al transporte de carga a granel l\u00edquida de \u00a0ciento cincuenta (150) toneladas o m\u00e1s de arqueo bruto, requieren de \u00a0clasificaci\u00f3n internacional. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. La carga \u00a0refrigerada se considerar\u00e1, seg\u00fan sea el caso, como carga general o como carga \u00a0a granel, de acuerdo con el volumen y forma de efectuar tal transporte. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 40. \u00a0AUTORIZACION DE FLETAMENTO O ARRENDAMIENTO DE NAVES PARA TRANSPORTE MARITIMO. \u00a0DIMAR tramitar\u00e1 las solicitudes de autorizaci\u00f3n de fletamento o arrendamiento \u00a0de naves de que trata el art\u00edculo 155 del Decreto 2324 de 1984, \u00a0siempre que se cumpla con los siguientes requisitos: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Que sea presentada \u00a0por el armador colombiano interesado o por el usuario importador o exportador, \u00a0antes de la celebraci\u00f3n del contrato. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Se anexe la \u00a0siguiente informaci\u00f3n: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) EL ARMADOR \u00a0INFORMARA: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">i) Nombre, bandera, \u00a0caracter\u00edsticas generales y clasificaci\u00f3n de la nave. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">ii) Clase y cantidad \u00a0de carga a transportar. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">iii) Ruta o servicio a \u00a0la cual se asignar\u00e1 la nave o en su defecto puertos de origen y destino de la \u00a0carga. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">iv) Fechas entre las \u00a0cuales se utilizar\u00e1 la nave. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">v) Toneladas de carga \u00a0que transportar\u00e1 bajo protecci\u00f3n de reserva de carga y las toneladas libres, \u00a0cuando la nave no fuere colombiana. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) EL USUARIO, \u00a0IMPORTADOR O EXPORTADOR INFORMARA: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">i) Clase y cantidad de \u00a0carga a transportar. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">ii) Puerto de origen y \u00a0destino de la carga. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">iii) Fechas entre las \u00a0cuales proyecta realizar el cargue. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">iv) Copia del registro \u00a0o licencia de importaci\u00f3n o del permiso de introducci\u00f3n de mercanc\u00edas a Zona \u00a0Franca. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">v) Cuando se trate del \u00a0transporte de mercanc\u00edas correspondientes al porcentaje libre de reserva de \u00a0carga, copia del conocimiento de embarque bajo el cual se transport\u00f3 el \u00a0porcentaje reservado, o indicaci\u00f3n del n\u00famero del registro del contrato de \u00a0fletamento respectivo, o cualquier otra prueba de haber cumplido con el \u00a0transporte del porcentaje amparado por Reserva de Carga. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">vi) Indicaci\u00f3n del \u00a0n\u00famero de la comunicaci\u00f3n, mediante la cual DIMAR autoriz\u00f3 el levantamiento de \u00a0la Reserva de Carga, cuando fuere procedente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo 1\u00ba Las naves \u00a0que se fleten o arrienden deben disponer de la m\u00e1s alta clasificaci\u00f3n vigente, \u00a0expedida por una Sociedad Clasificadora Internacional reconocida por la \u00a0Autoridad Mar\u00edtima y poseer vigentes las garant\u00edas o seguros correspondientes, \u00a0seg\u00fan la carga que se transporte, y en especial las relativas a los riesgos de \u00a0contaminaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo 2\u00ba Los \u00a0denominados &#8220;Fletamentos de Espacio&#8221; se someter\u00e1n a los mismos \u00a0requisitos que fija este art\u00edculo. Los fletamentos por tiempo que soliciten los \u00a0armadores colombianos, s\u00f3lo deber\u00e1n cumplir con los numerales (i), (iii) y (iv) \u00a0del literal &#8220;a&#8221;. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 41. PLAZO DE \u00a0LA AUTORIZACION. Recibida la solicitud con el lleno de los requisitos fijados \u00a0en el art\u00edculo anterior, la Autoridad Mar\u00edtima verificar\u00e1 el porcentaje \u00a0disponible para fletamento que tenga el armador interesado, el cumplimiento de \u00a0las normas de Reserva de Carga y las dem\u00e1s normas de la marina mercante \u00a0aplicables, y decidir\u00e1 dentro de los dos (2) d\u00edas h\u00e1biles siguientes a la \u00a0presentaci\u00f3n de la solicitud. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. La \u00a0autorizaci\u00f3n establecer\u00e1 el per\u00edodo de utilizaci\u00f3n de la nave para los \u00a0armadores y cuando fuere solicitada por los usuarios el lapso dentro del cual \u00a0deber\u00e1 completarse el cargue; vencidos estos plazos sin que la nave se hubiese \u00a0utilizado o el cargue hubiere culminado, la autorizaci\u00f3n quedara sin valor ni \u00a0efecto, salvo que existiendo justificaciones \u00e9stas se informen a DIMAR y se \u00a0solicite la pr\u00f3rroga correspondiente; s\u00f3lo podr\u00e1 otorgarse una pr\u00f3rroga y por \u00a0un per\u00edodo m\u00e1ximo de quince (15) d\u00edas calendario. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 42. REGISTRO \u00a0DE CONTRATOS. Es obligaci\u00f3n de los armadores o usuarios interesados que los \u00a0contratos de fletamento o arrendamiento de naves sean registrados ante la \u00a0Autoridad Mar\u00edtima, dentro de los veinte (20) d\u00edas siguientes, contados a \u00a0partir de la fecha de la autorizaci\u00f3n respectiva. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Los contratos de \u00a0fletamentos de naves que se ejecuten en desarrollo de ventas de productos de \u00a0exportaci\u00f3n de Colombia en t\u00e9rminos &#8220;FOB&#8221;, no est\u00e1n sujetos a \u00a0autorizaci\u00f3n ni registro. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Todos los \u00a0contratos de fletamento a arrendamiento de naves que requieran los usuarios y \u00a0que no sean celebrados por armadores colombianos, deber\u00e1n concertarse por \u00a0intermedio de un Corredor de Contratos de Fletamento o Arrendamiento de Naves \u00a0con licencia vigente, y ser\u00e1 \u00e9ste quien lo presentar\u00e1 dentro del plazo antes \u00a0anotado para registro ante DIMAR. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 43. ANEXOS \u00a0PARA EL REGISTRO. Deber\u00e1 presentarse para el registro de los contratos de \u00a0fletamento o arrendamiento de naves el original y la copia del respectivo \u00a0contrato debidamente firmados. El original con la constancia de registro ser\u00e1 \u00a0devuelto solamente al armador o al corredor interesado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 44. \u00a0ECOPETROL. La Empresa Colombiana de Petr\u00f3leos Ecopetrol, podr\u00e1 fletar \u00a0directamente y sin necesidad de mediar un Corredor de Contratos de Fletamento o \u00a0Arrendamiento de Naves con licencia vigente, \u00fanicamente aquellas naves que requiera \u00a0para el transporte de importaci\u00f3n o exportaci\u00f3n de hidrocarburos y derivados de \u00a0su propiedad. En tal caso corresponde a Ecopetrol solicitar la respectiva \u00a0autorizaci\u00f3n a la Autoridad Mar\u00edtima y cumplir directamente con el registro del \u00a0contrato. Esta autorizaci\u00f3n especial para Ecopetrol no conlleva en forma alguna \u00a0exoneraci\u00f3n al cumplimiento de las normas de Reserva de Carga. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 45. \u00a0INCUMPLIMIENTO DE REQUISITOS SOBRE FLETAMENTO O ARRENDAMIENTO DE NAVES. Cuando \u00a0DIMAR determine que no se ha cumplido con los requisitos o condiciones de los \u00a0art\u00edculos precedentes, o que la informaci\u00f3n suministrada no corresponde a la \u00a0realidad, o que la clasificaci\u00f3n de las naves no est\u00e1 vigente, o ha sido \u00a0suspendida o no corresponde a la exigida, o que las garant\u00edas para responder \u00a0por riesgos de contaminaci\u00f3n no son suficientes o no est\u00e1n vigentes, si la nave \u00a0a\u00fan no hubiere empezado la operaci\u00f3n de cargue podr\u00e1 cancelar la autorizaci\u00f3n \u00a0de fletamento o arrendamiento concedida sin perjuicio de aplicar las sanciones correspondientes. \u00a0Si la nave ya hubiere iniciado el cargue podr\u00e1 prohibirse el ingreso a aguas \u00a0colombianas hasta tanto se subsane debidamente la anomal\u00eda encontrada. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">En todo caso, DIMAR \u00a0podr\u00e1 imponer las sanciones establecidas en el art\u00edculo 80 del Decreto 2324 de 1984 \u00a0a los responsables, sean tanto el fletador, el corredor de contratos de \u00a0fletamento, como el armador. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Esta \u00a0cancelaci\u00f3n de la autorizaci\u00f3n de fletamento o arrendamiento de nave, se \u00a0notificar\u00e1 conforme al art\u00edculo 44 del C\u00f3digo Contencioso Administrativo, bien \u00a0al armador, al usuario, o al corredor. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 46. CAPACIDAD \u00a0MAXIMA DE FLETAMENTO. A fin de determinar la capacidad m\u00e1xima de fletamento o \u00a0arrendamiento de naves a que tiene derecho un armador colombiano, conforme lo \u00a0dispone el art\u00edculo 156 del Decreto 2324 de 1984, \u00a0se deber\u00e1 sumar por especialidades el tonelaje de peso muerto de las naves de \u00a0bandera colombiana de su propiedad, que tenga en operaci\u00f3n, en las rutas o \u00a0servicios que le hayan sido autorizadas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Con base en los \u00a0anteriores resultados, se aplicar\u00e1n los porcentajes de que trata el art\u00edculo \u00a0que se reglamenta. Los tonelajes de peso muerto de naves de una especialidad no \u00a0generan capacidad de fletamento para naves de diferente especialidad. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Las naves \u00a0tomadas en fletamento por sustituci\u00f3n se consideran como tonelaje nacional y de \u00a0acuerdo con su especialidad generan ellas capacidad de fletamento en los \u00a0porcentajes a que se refiere el art\u00edculo que se reglamenta, pero perdi\u00e9ndola la \u00a0nave sustituida. Las naves extranjeras tomadas en arrendamiento financiero o \u00a0&#8220;Leasing&#8221; y las de propiedad de armadores colombianos, pero bajo \u00a0bandera extranjera, no generan capacidad de fletamento para los efectos del \u00a0art\u00edculo 156 del Decreto 2324 de 1984. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 47. COMPUTO \u00a0DE TONELAJE EN FLETAMENTO. Los tonelajes de fletamento se computar\u00e1n a partir \u00a0de la fecha consignada en la autorizaci\u00f3n de fletamento hasta la fecha de \u00a0arribo al primer puerto colombiano cuando la nave va a devolverse en Colombia, \u00a0o de lo contrario en la fecha de arribo al puerto extranjero en que deba \u00a0entregarse. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 48. NAVES QUE \u00a0NO SE COMPUTAN. Para los efectos de que trata el art\u00edculo 156 del Decreto 2324 de 1984, \u00a0no se imputar\u00e1n o no afectar\u00e1n el n\u00famero de toneladas de peso muerto a que \u00a0tiene derecho a fletar un armador colombiano, las siguientes naves: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Las destinadas \u00a0exclusivamente para el transporte de carga de exportaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Numeral derogado por el Decreto 143 de 1988, \u00a0art\u00edculo 26. Las \u00a0destinadas para el transporte de carga no reservada. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Las destinadas para \u00a0el transporte de carga entre terceros pa\u00edses. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4. Las naves tomadas \u00a0en arrendamiento financiero o &#8220;Leasing&#8221;, siempre que hubiere mediado \u00a0resoluci\u00f3n de DIMAR para autorizar tal contrato. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">5. Numeral derogado por el Decreto 501 de 1990, \u00a0art\u00edculo 32 y por el Decreto 143 de 1988, \u00a0art\u00edculo 26. . Las naves de propiedad del armador colombiano que \u00a0transitoriamente navegan bajo pabell\u00f3n extranjero. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 49. Derogado por el Decreto 501 de 1990, \u00a0art\u00edculo 32 y por el Decreto 143 de 1988, \u00a0art\u00edculo 26. NO \u00a0ACUMULACION. Cuando en una nave fletada se transporte carga a granel reservada \u00a0y carga a granel libre de reserva de carga se computar\u00e1 \u00fanicamente el tonelaje \u00a0de peso muerto que porcentualmente corresponda a la cantidad de carga \u00a0reservada, siempre y cuando con la solicitud de autorizaci\u00f3n de fletamento se \u00a0haya informado a DIMAR las cantidades de una y otra, y siempre que el usuario, \u00a0importador o exportador haya aceptado no acumular los tonelajes libres para los \u00a0efectos del art\u00edculo 162, inciso segundo del Decreto 2324 de 1984. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Es obligaci\u00f3n del armador interesado entregar a \u00a0DIMAR, simult\u00e1neamente con la solicitud de autorizaci\u00f3n, la constancia escrita \u00a0por medio de la cual el usuario acepta en forma expresa la no acumulaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 50. \u00a0ARRENDAMIENTO FINANCIERO. Cuando un armador colombiano desee tomar en \u00a0arrendamiento, del denominado financiero o &#8220;Leasing&#8221;, una nave \u00a0extranjera deber\u00e1 presentar previamente solicitud a la Direcci\u00f3n General \u00a0Mar\u00edtima y Portuaria, quien podr\u00e1 autorizarlo siempre que se cumplan los \u00a0siguientes requisitos: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Que el total del \u00a0tonelaje de peso muerto de las naves a tomarse en arrendamiento financiero no \u00a0exceda del cincuenta por ciento (50%) del tonelaje de peso muerto de propiedad \u00a0del armador en bandera colombiana, que se encuentre en operaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Que se anexe el \u00a0proyecto de contrato de arrendamiento financiero o &#8220;leasing&#8221;, el cual \u00a0tiene que incorporar una opci\u00f3n de compra irrevocable en favor del armador \u00a0colombiano, la cual deber\u00e1 ejercerse a m\u00e1s tardar a los cinco (5) a\u00f1os de \u00a0iniciado el contrato. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Un compromiso \u00a0escrito del armador arrendatario, en el sentido de que dar\u00e1 cumplida aplicaci\u00f3n \u00a0a lo dispuesto en el art\u00edculo 101 del Decreto 2324 de 1984. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4. Fotocopia aut\u00e9ntica \u00a0de los documentos de clasificaci\u00f3n vigentes de la nave, con sus respectivas \u00a0traducciones al castellano. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">5. Nombre, bandera, \u00a0caracter\u00edsticas generales de la nave, y plena identificaci\u00f3n del propietario. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">6. Indicar la ruta o \u00a0servicio a la cual se asignar\u00e1 la nave. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">7. Que la nave no \u00a0tenga m\u00e1s de diez a\u00f1os de construida. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">8. Se anexar\u00e1 la carta \u00a0de intenci\u00f3n de una asociaci\u00f3n o club de protecci\u00f3n e indemnizaci\u00f3n \u00a0internacional, que haya cumplido con los requisitos del par\u00e1grafo del art\u00edculo \u00a072 del Decreto 2324 de 1984, \u00a0o de un asegurador legalmente establecido en Colombia que ofrezca dar los \u00a0amparos correspondientes por eventual responsabilidad frente a terceros, por lo \u00a0menos hasta por el 100% del valor asegurado de la nave en la p\u00f3liza de casco. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">9. Copia y traducci\u00f3n \u00a0de la p\u00f3liza de casco y maquinaria vigente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">10. Si se trata de un \u00a0buque tanquero para transporte de hidrocarburos o sustancias eventualmente \u00a0contaminantes, tambi\u00e9n se acompa\u00f1ar\u00e1 una copia aut\u00e9ntica de la p\u00f3liza de seguro \u00a0o amparo de responsabilidad civil extracontractual por eventual contaminaci\u00f3n, \u00a0hasta por lo menos el 100% del valor asegurado de la nave en la p\u00f3liza de \u00a0casco. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">11. El valor comercial \u00a0estimado de la nave a la fecha de presentaci\u00f3n de la solicitud, debidamente \u00a0sustentado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 51. PERFECCIONAMIENTO \u00a0DEL CONTRATO. Autorizado el arrendamiento financiero o &#8220;Leasing&#8221;, el \u00a0contrato deber\u00e1 perfeccionarse dentro de los sesenta (60) d\u00edas siguientes a que \u00a0quede en firme la resoluci\u00f3n correspondiente. Dentro de los treinta (30) d\u00edas \u00a0siguientes al perfeccionamiento del contrato, deber\u00e1 entregar a DIMAR el \u00a0armador interesado, los siguientes documentos: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Copia aut\u00e9ntica del \u00a0contrato con firmas legalizadas, tanto del propietario de la nave, como del \u00a0arrendatario. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Compromiso elevado \u00a0a escritura p\u00fablica, por medio del cual el armador colombiano se obliga frente \u00a0a la Autoridad Mar\u00edtima Colombiana a: i) que durante todo el tiempo en que \u00a0tenga esta nave en arriendo o &#8220;Leasing&#8221; mantendr\u00e1 naves propias \u00a0suficientes a fin de cumplir siempre con la condici\u00f3n del numeral 1 del \u00a0art\u00edculo 50 anterior; ii) que matricular\u00e1 bajo bandera colombiana finalmente \u00a0esta nave, dentro de los noventa (90) d\u00edas siguientes a que ejerza la opci\u00f3n de \u00a0compra, y iii) aceptando en forma expresa que si esto no ocurriese pagar\u00e1 por \u00a0su incumplimiento a la Naci\u00f3n colombiana el 10% del valor comercial del buque \u00a0referido a la fecha de celebraci\u00f3n \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">del contrato o entrega \u00a0de la nave, el que fuere m\u00e1s alto, por cada a\u00f1o o proporcionalmente por cada \u00a0d\u00eda de explotaci\u00f3n de la nave. Esta se causar\u00e1 por el s\u00f3lo hecho de incumplir \u00a0su compromiso final de abanderamiento de tal nave en Colombia. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Al armador colombiano \u00a0que incumpla esta obligaci\u00f3n sin que haya probado una causal de exoneraci\u00f3n \u00a0v\u00e1lida, no podr\u00e1 aprob\u00e1rsele ning\u00fan otro contrato de este mismo tipo por un \u00a0per\u00edodo de cinco (5) a\u00f1os, contados a partir del incumplimiento. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Las \u00fanicas \u00a0causales de exoneraci\u00f3n del pago de la multa para el armador colombiano en caso \u00a0de no dar en tiempo cumplimiento a su obligaci\u00f3n de abanderar en Colombia la \u00a0nave tomada en arrendamiento financiero o &#8220;Leasing&#8221; son: el \u00a0hundimiento o la p\u00e9rdida total de la nave sin su culpa, o acreditar una \u00a0circunstancia constitutiva de fuerza mayor. Por la sola cancelaci\u00f3n o \u00a0terminaci\u00f3n del contrato sin ejercer afirmativamente la opci\u00f3n de compra se \u00a0presumir\u00e1 el incumplimiento del armador colombiano a su obligaci\u00f3n de \u00a0abanderamiento. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 52. NAVES DE \u00a0BANDERA EXTRANJERA PROPIEDAD DE ARMADORES COLOMBIANOS. Podr\u00e1n los armadores \u00a0colombianos adquirir naves de bandera extranjera, las que gozar\u00e1n del beneficio \u00a0de la reserva de carga, no obstante permanecer matriculadas en puerto \u00a0extranjero y bajo bandera extranjera, siempre y cuando la compra sea autorizada \u00a0por la Direcci\u00f3n General Mar\u00edtima y Portuaria, mediando solicitud del \u00a0interesado en la que deber\u00e1 demostrar lo siguiente: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Que el armador \u00a0colombiano tiene buques de su propiedad bajo bandera colombiana y en operaci\u00f3n, \u00a0cuyo tonelaje de peso muerto es equivalente al menos al 100% del tonelaje de \u00a0peso muerto de la nave o naves que pretende adquirir. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Que la nave a \u00a0adquirir es del mismo tipo de las propias. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Que la raz\u00f3n \u00a0fundamental para mantener bajo bandera extranjera la nave que se pretende \u00a0adquirir obedece a una exigencia de quien financia la nave, y que el cambio de abanderamiento \u00a0a bandera colombiana implica la cancelaci\u00f3n o sustituci\u00f3n del cr\u00e9dito \u00a0originalmente otorgado para la construcci\u00f3n de \u00e9sta, modificaci\u00f3n que conlleva \u00a0una desmejora importante de las tasas de inter\u00e9s, plazos o dem\u00e1s condiciones \u00a0financieras del cr\u00e9dito. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4. El compromiso que \u00a0dentro de un per\u00edodo m\u00e1ximo de cinco (5) a\u00f1os, contados a partir del \u00a0perfeccionamiento de la compraventa, abanderar\u00e1 y matricular\u00e1 en Colombia la \u00a0nave de que se trate. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Deber\u00e1 anexar a la \u00a0solicitud adem\u00e1s la fotocopia aut\u00e9ntica de los documentos de clasificaci\u00f3n \u00a0vigentes de la nave con sus respectivas traducciones al castellano, indicar\u00e1 la \u00a0ruta o servicio al cual se asignar\u00e1 y la manifestaci\u00f3n de que la nave no tiene \u00a0m\u00e1s de diez (10) a\u00f1os de construida, as\u00ed como los dem\u00e1s documentos propios para \u00a0solicitar el permiso de inversi\u00f3n en naves. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 53. \u00a0AUTORIZACION PARA MANTENER NAVES BAJO BANDERA EXTRANJERA. Si la Direcci\u00f3n \u00a0General Mar\u00edtima y Portuaria encuentra que la solicitud de que trata el \u00a0art\u00edculo anterior re\u00fane los requisitos que all\u00ed se enuncian, y siempre que se \u00a0le haya demostrado a satisfacci\u00f3n las circunstancias que justifican el mantener \u00a0bajo bandera extranjera dicha nave, podr\u00e1 entonces autorizar al armador \u00a0colombiano para adquirirla y mantenerla bajo bandera extranjera por un per\u00edodo \u00a0m\u00e1ximo de cinco (5) a\u00f1os. En la misma resoluci\u00f3n se indicar\u00e1 que tal nave se \u00a0asimila a una de bandera colombiana para los efectos de la reserva de carga, a \u00a0partir de la fecha en que el armador interesado cumpla con los siguientes requisitos \u00a0adicionales: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Que otorgue por \u00a0escritura p\u00fablica un compromiso que asegure que a m\u00e1s tardar al final del \u00a0per\u00edodo que se le autoriz\u00f3, matricular\u00e1 en Colombia la nave de que se trate. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Que en tal nave \u00a0tanto el capit\u00e1n, los oficiales y al menos el 80% de la tripulaci\u00f3n sean \u00a0colombianos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Que a bordo las \u00a0\u00f3rdenes verbales y escritas se den en lengua castellana y que los libros de la \u00a0nave se lleven en este idioma, o si no se pudiere por disposiciones del pa\u00eds \u00a0del registro del buque, se lleven copias en lengua castellana. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4. Que constituya y \u00a0entregue una garant\u00eda, a satisfacci\u00f3n de DIMAR, por el 10% del valor comercial \u00a0de la nave por cada a\u00f1o de plazo que se le haya autorizado, a efecto de \u00a0garantizar a la Autoridad Mar\u00edtima Colombiana que al final del per\u00edodo \u00a0concedido abanderar\u00e1 la nave bajo pabell\u00f3n nacional. La cauci\u00f3n anterior no se \u00a0har\u00e1 efectiva cuando el armador demuestre que el incumplimiento de su \u00a0obligaci\u00f3n de abanderar la nave bajo pabell\u00f3n colombiano obedeci\u00f3 a una de las \u00a0circunstancias enunciadas en el par\u00e1grafo del art\u00edculo 51 anterior. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. La nave \u00a0extranjera adquirida conforme a estos art\u00edculos perder\u00e1 IPSO FACTO el beneficio \u00a0de asimilarse a nave de bandera colombiana desde cuando el armador colombiano \u00a0propietario deje de cumplir con lo establecido en el numeral 1 del art\u00edculo 52 \u00a0anterior. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 54. NAVES CON \u00a0BENEFICIO DE RESERVA DE CARGA. Tendr\u00e1n el beneficio de la reserva de carga \u00a0adem\u00e1s de las naves de bandera colombiana, las que se asimilan a estas y que \u00a0son: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Las naves fletadas \u00a0o arrendadas por armadores colombianos conforme a lo dispuesto en los art\u00edculos \u00a0155 y 156 del Decreto 2324 de 1984 \u00a0y dem\u00e1s normas concordantes; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Las naves fletadas \u00a0por sustituci\u00f3n, ya se trate por reparaciones mayores o p\u00e9rdida accidental de \u00a0naves de bandera colombiana, conforme lo dispone el art\u00edculo 158 del Decreto 2324 de 1984; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Las naves tomadas \u00a0en arrendamiento financiero o &#8220;Leasing&#8221;, con el lleno de los \u00a0requisitos de que trata el presente Decreto; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Las naves de \u00a0propiedad de armadores colombianos que naveguen bajo pabell\u00f3n extranjero, \u00a0siempre que se hayan llenado los requisitos fijados en el presente Decreto; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Las naves de \u00a0armadores extranjeros que hayan suscrito acuerdos de asociaci\u00f3n con armadores colombianos, \u00a0con el lleno de los requisitos de los art\u00edculos 147 y 148 del Decreto 2324 de 1984. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 55. Derogado por el Decreto 1478 de 1992, \u00a0art\u00edculo 6\u00ba. OTORGAMIENTO \u00a0DE RUTAS DE CABOTAJE. De acuerdo con lo establecido en el art\u00edculo 152 del \u00a0Decreto 2324 de 1984, para la adjudicaci\u00f3n de rutas de cabotaje para el \u00a0transporte de carga general o carga a granel que se proyecten servir con naves, \u00a0cuyo tonelaje sea superior a 200 toneladas de arqueo bruto, la solicitud ser\u00e1 \u00a0presentada por conducto de una Capitan\u00eda de Puerto localizada dentro de la ruta \u00a0objeto de la autorizaci\u00f3n y se seguir\u00e1 el procedimiento establecido en el \u00a0art\u00edculo 160 del Decreto 2324 de 1984, \u00a0con las siguientes modificaciones: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. No se har\u00e1 manifestaci\u00f3n sobre reserva de carga. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Recibida la documentaci\u00f3n, la Capitan\u00eda de Puerto \u00a0la remitir\u00e1 a la Direcci\u00f3n General Mar\u00edtima y Portuaria acompa\u00f1ada de su \u00a0concepto sobre la necesidad y conveniencia del servicio solicitado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 56. Derogado por el Decreto 1478 de 1992, \u00a0art\u00edculo 6\u00ba. Modificado por el Decreto 143 de 1988, \u00a0art\u00edculo 23. OTORGAMIENTO DE RUTAS DE CABOTAJE PARA NAVES HASTA DE 200 TONELADAS DE \u00a0ARQUEO BRUTO. Cuando la ruta de cabotaje se proyecte servir con naves hasta de \u00a0200 toneladas de arqueo bruto, el solicitante deber suministrar la informaci\u00f3n \u00a0contenida en el art\u00edculo 160 del Decreto 2324 de 1984, \u00a0pero no ser\u00e1 necesario ni el estudio de cargas ni \u00a0la manifestaci\u00f3n sobre reserva de carga a que se refieren los literales e) y f) \u00a0y para su autorizaci\u00f3n se observa el siguiente tr\u00e1mite: Recibida la \u00a0documentaci\u00f3n por una Capitan\u00eda de Puerto localizada dentro de la ruta objeto \u00a0de la petici\u00f3n, \u00c9sta proceder a tramitarla al Director General Mar\u00edtimo y \u00a0Portuario dentro de los cinco (5) d\u00edas siguientes a su presentaci\u00f3n acompa\u00f1ada \u00a0de un concepto sobre la conveniencia y necesidad del servicio solicitado. La \u00a0resoluci\u00f3n que resuelva la petici\u00f3n se expedir\u00e1 dentro de los quince (15) d\u00edas \u00a0siguientes a la fecha de recibo de la documentaci\u00f3n en la Direcci\u00f3n General \u00a0Mar\u00edtima y Portuaria. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Cuando la petici\u00f3n se refiera a transporte conjunto de pasajeros y de \u00a0carga, la Capitan\u00eda de Puerto deber\u00e1 remitir con la documentaci\u00f3n, los \u00a0resultados de la inspecci\u00f3n de que trata el art\u00edculo 66 del Decreto 2451 de 1986. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Texto inicial del art\u00edculo \u00a056. \u201cOTORGAMIENTO \u00a0DE RUTAS PARA NAVES HASTA DE 200 TONELADAS DE ARQUEO BRUTO. Cuando la ruta de \u00a0cabotaje se proyecte servir con naves hasta de 200 toneladas de arqueo bruto, \u00a0no ser\u00e1 necesario ni el estudio de cargas ni la manifestaci\u00f3n sobre reserva de \u00a0carga a que se refieren los literales e) y f) del art\u00edculo 160 del Decreto 2324 de 1984 y para su autorizaci\u00f3n se observar\u00e1 el siguiente \u00a0tr\u00e1mite: recibida la documentaci\u00f3n por una Capitan\u00eda de Puerto localizada \u00a0dentro de la ruta objeto de la autorizaci\u00f3n, \u00e9sta ordenar\u00e1 la publicaci\u00f3n del \u00a0texto o un extracto de la misma, conforme a los art\u00edculos 15 y 16 del C\u00f3digo \u00a0Contencioso Administrativo y adem\u00e1s deber\u00e1 el interesado a su costa, ordenar su \u00a0lectura por la emisora local en tres (3) d\u00edas diferentes. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Las oposiciones \u00a0podr\u00e1n presentarse hasta diez (10) d\u00edas despu\u00e9s de hecha la \u00faltima de las \u00a0publicaciones de que aqu\u00ed se trata. Estas deber\u00e1n presentarse por escrito y ser \u00a0motivadas. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Vencido el \u00a0t\u00e9rmino anterior, la Capitan\u00eda de Puerto remitir\u00e1 la actuaci\u00f3n surtida al \u00a0Director General Mar\u00edtimo y Portuario acompa\u00f1ada de su concepto sobre la \u00a0conveniencia y necesidad del servicio solicitado. Si se hubiese formulado \u00a0oposici\u00f3n a la misma, remitir\u00e1 tambi\u00e9n los escritos respectivos y en este caso \u00a0se decidir\u00e1 por la Autoridad Mar\u00edtima si se ordena la realizaci\u00f3n de audiencia \u00a0o se resuelve con base en los escritos presentados por los opositores y el \u00a0solicitante. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La petici\u00f3n se \u00a0resolver\u00e1 dentro de los quince (15) d\u00edas siguientes a la fecha de su recibo en \u00a0la Direcci\u00f3n General Mar\u00edtima y Portuaria, o a los cinco (5) d\u00edas de celebrada \u00a0la audiencia.\u201d. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 57. Derogado por el Decreto 1478 de 1992, \u00a0art\u00edculo 6\u00ba. CONTENIDO \u00a0DE LAS AUTORIZACIONES. Las rutas de cabotaje, a juicio de la Direcci\u00f3n General \u00a0Mar\u00edtima y Portuaria, ser\u00e1n autorizadas en consideraci\u00f3n a los intereses \u00a0generales y buscando garantizar un servicio adecuado, estable, racionalizado, \u00a0seguro y confiable, bien a un armador y todas sus naves, o restringirla a \u00a0ciertas naves espec\u00edficas de tal armador o para productos determinados, sin perjuicio \u00a0de lo dispuesto en el art\u00edculo 152 del Decreto 2324 de 1984. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 58. Derogado por el Decreto 1478 de 1992, \u00a0art\u00edculo 6\u00ba. VARIACION \u00a0DE CARGA O INCREMENTO DE NAVES EN RUTAS DE CABOTAJE. La Direcci\u00f3n General \u00a0Mar\u00edtima y Portuaria podr\u00e1 espor\u00e1dicamente y previa solicitud motivada del \u00a0armador interesado, autorizar la variaci\u00f3n de la carga o el incremento del \u00a0n\u00famero de naves inicialmente autorizadas, siempre que tal variaci\u00f3n o \u00a0incremento no tenga una vigencia superior a sesenta (60) d\u00edas y que no afecte \u00a0los servicios concedidos en la misma ruta u otros armadores. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">De lo contrario la solicitud se tramitar\u00e1 conforme \u00a0al art\u00edculo 55 anterior. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 59. SERVICIO \u00a0DE CABOTAJE. Para los efectos del art\u00edculo 151 y del par\u00e1grafo del art\u00edculo 152 \u00a0del Decreto 2324 de 1984, \u00a0cuando la Autoridad Mar\u00edtima determine que no se encuentran disponibles naves de \u00a0bandera colombiana o con capacidad de prestar el servicio de cabotaje, se podr\u00e1 \u00a0autorizar el transporte en artefactos navales registrados en Colombia, siempre \u00a0que \u00e9stos ofrezcan condiciones suficientes de seguridad, para el tipo de carga \u00a0y transporte de que se trate. Si tampoco hubiere en disponibilidad artefactos \u00a0navales registrados en Colombia, o si \u00e9stos no tuvieren las condiciones de \u00a0seguridad adecuadas, s\u00f3lo entonces podr\u00e1 autorizarse el empleo de naves \u00a0extranjeras. El transporte en artefacto naval podr\u00e1 realizarlo el armador, \u00a0operador o propietario colombiano. Si el transporte ha de realizarse en naves \u00a0extranjeras, \u00e9ste deber\u00e1 efectuarse a trav\u00e9s del transportador colombiano \u00a0beneficiario de la ruta. Si \u00e9ste no estuviere interesado se autorizar\u00e1, por \u00a0excepci\u00f3n, la contrataci\u00f3n directa entre el usuario y el armador extranjero \u00a0para un viaje determinado. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 60. CARGA DE \u00a0CABOTAJE. La calificaci\u00f3n de servicio de transporte internacional a que se \u00a0refiere el par\u00e1grafo del art\u00edculo 143 del Decreto 2324 de 1984, \u00a0no obsta para que la carga nacional o nacionalizada efectivamente transportada \u00a0de un puerto colombiano a otro, sea considerada como carga de cabotaje, en \u00a0especial para los efectos de las tarifas portuarias. Lo aqu\u00ed previsto no se \u00a0aplicar\u00e1 a los cargamentos en tr\u00e1nsito internacional, ni a los de importaci\u00f3n \u00a0en tr\u00e1nsito nacional, ni de importaci\u00f3n a la carga en tr\u00e1nsito nacional \u00a0reembarcada. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 61. \u00a0EXCLUSIVIDAD PARA CABOTAJE Y CARGAS INTERNACIONALES. Los armadores que s\u00f3lo \u00a0tengan asignadas rutas de cabotaje no est\u00e1n autorizados para movilizar carga de \u00a0tr\u00e1fico internacional. A su vez, los armadores que s\u00f3lo tengan asignadas rutas \u00a0internacionales no podr\u00e1n movilizar cargas de cabotaje. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Los \u00a0armadores colombianos con rutas internacionales podr\u00e1n transportar \u00a0ocasionalmente cargas de cabotaje, siempre que los armadores autorizados para \u00a0movilizar estas cargas no est\u00e9n en capacidad de hacerlo, y mediando permiso \u00a0previo de la Autoridad Mar\u00edtima Nacional. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 62. RUTAS DE \u00a0CABOTAJE PARA TRANSPORTE DE PASAJEROS. La solicitud de autorizaci\u00f3n para servicio \u00a0p\u00fablico de transporte mar\u00edtimo de cabotaje de pasajeros, se presentar\u00e1 por \u00a0conducto de una Capitan\u00eda de Puerto localizada dentro de la ruta que se \u00a0proyecta servir, acompa\u00f1ada de la siguiente informaci\u00f3n: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Identificaci\u00f3n del \u00a0solicitante. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Puertos entre los \u00a0cuales prestar\u00e1 el servicio. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Frecuencias. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">4. Nombre de las naves \u00a0de bandera colombiana con que operar\u00e1 la ruta. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">5. Fotocopia aut\u00e9ntica \u00a0de los certificados de clasificaci\u00f3n definitiva, n\u00famero m\u00e1ximo de pasajeros y tripulantes, \u00a0de seguridad para buque de pasaje, de inspecci\u00f3n de equipo de \u00a0radio-comunicaciones y de inspecci\u00f3n de equipo contra incendio de tales naves. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">6. Copia de la \u00a0inspecci\u00f3n practicada por la Capitan\u00eda de Puerto, en la que se detallar\u00e1n al \u00a0menos los siguientes aspectos de la nave: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Condiciones \u00a0relativas a la seguridad de la vida humana en el mar; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Elementos b\u00e1sicos \u00a0de comodidad para los pasajeros; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Descripci\u00f3n de los \u00a0equipos de radio-comunicaci\u00f3n y su estado de operabilidad; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Las dem\u00e1s observaciones \u00a0pertinentes. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">7. Si el solicitante \u00a0no cuenta con una nave de bandera colombiana presentar\u00e1 el plan de \u00a0adquisiciones. En este caso no podr\u00e1 iniciarse el servicio respectivo hasta \u00a0cuando DIMAR haya aprobado los informes y anexos de que tratan los numerales 5 \u00a0y 6 anteriores y una vez la nave haya sido matriculada en Colombia. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Si la ruta se proyecta \u00a0servir con una nave cuyo tonelaje sea superior a 50 toneladas de arqueo bruto, \u00a0su tr\u00e1mite y autorizaci\u00f3n se regir\u00e1n por el procedimiento indicado en el art\u00edculo \u00a055 del presente Decreto. Si el tonelaje de la nave o naves es inferior a 50 \u00a0toneladas de arqueo bruto, se dar\u00e1 aplicaci\u00f3n a lo dispuesto en el art\u00edculo 56 \u00a0del presente Decreto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 63. \u00a0TRANSPORTE DE PASAJEROS EN LOCALIDADES SITUADAS DENTRO DE LA JURISDICCION DE \u00a0UNA MISMA CAPITANIA. La autorizaci\u00f3n para la prestaci\u00f3n del servicio p\u00fablico de \u00a0transporte de pasajeros entre localidades situadas dentro del \u00e1rea de \u00a0jurisdicci\u00f3n de una misma capitan\u00eda se tramitar\u00e1 conforme a lo dispuesto en el \u00a0art\u00edculo anterior y adem\u00e1s el solicitante deber\u00e1 anexar los siguientes \u00a0documentos: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Concepto favorable \u00a0de la Oficina Regional de la Corporaci\u00f3n Nacional de Turismo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Autorizaci\u00f3n de la \u00a0Oficina Regional del Inderena, cuando el servicio incluya localidades que hayan \u00a0sido declaradas como parques naturales. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 64. N\u00daMERO \u00a0MAXIMO DE PASAJEROS. En la resoluci\u00f3n que autorice la prestaci\u00f3n de servicio \u00a0p\u00fablico de transporte de pasajeros, se determinar\u00e1 el n\u00famero m\u00e1ximo de \u00a0pasajeros que cada nave del solicitante puede transportar y el monto de la \u00a0p\u00f3liza de seguros por responsabilidad contractual frente a los usuarios o sus \u00a0causahabientes, que deber\u00e1 entregar a DIMAR, por conducto de la Capitan\u00eda de \u00a0Puerto respectiva, dentro de los treinta (30) d\u00edas siguientes a que quede en \u00a0firme tal providencia. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Si el solicitante no \u00a0posee nave de bandera colombiana el n\u00famero m\u00e1ximo de pasajeros ser\u00e1 fijado \u00a0cuando la nave haya sido matriculada en Colombia y disponga de los certificados \u00a0relacionados en el art\u00edculo anterior. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 65. TARIFAS \u00a0PARA TRANSPORTE DE PASAJEROS. Los armadores a los que se les haya autorizado el \u00a0servicio de transporte de pasajeros deber\u00e1n presentar para registro ante DIMAR \u00a0las tarifas respectivas, treinta (30) d\u00edas antes a aqu\u00e9l en que vayan a iniciar \u00a0la prestaci\u00f3n efectiva del servicio. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Las tarifas para \u00a0transporte de pasajeros a localidades situadas dentro del \u00e1rea de jurisdicci\u00f3n \u00a0de una misma Capitan\u00eda deber\u00e1n presentarse para registro ante DIMAR por \u00a0conducto de las Capitan\u00edas de Puerto, dentro del plazo antes anotado, \u00a0acompa\u00f1adas del concepto favorable de la Oficina Regional de la Corporaci\u00f3n \u00a0Nacional de Turismo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. Los \u00a0armadores que est\u00e9n prestando servicios de transporte de pasajeros tienen \u00a0cuatro (4) meses, contados a partir de la vigencia del presente Decreto para \u00a0obtener la autorizaci\u00f3n de que trata el art\u00edculo 62 anterior y para registrar \u00a0las tarifas correspondientes. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo \u00a066. Modificado por el Decreto 501 de 1990, \u00a0art\u00edculo 25. OTORGAMIENTO \u00a0DE RUTAS DE CABOTAJE PARA NAVES HASTA DE 200 TONELADAS DE ARQUEO BRUTO. \u00a0Cuando la ruta de cabotaje se proyecte servir \u00a0con naves hasta de 200 toneladas de arqueo bruto, el solicitante deber\u00e1 \u00a0suministrar la informaci\u00f3n contenida en el art\u00edculo 160 del Decreto 2324 de 1984, pero no ser\u00e1 necesario ni el estudio \u00a0de cargas ni la manifestaci\u00f3n sobre reserva de carga a que se refieren los \u00a0literales e) y f) y para su autorizaci\u00f3n se observar\u00e1 el siguiente tr\u00e1mite. \u00a0Recibida la documentaci\u00f3n por una capitan\u00eda de puerto localizada dentro de la \u00a0ruta objeto de la petici\u00f3n, \u00e9sta proceder\u00e1 a tramitarla al Director General \u00a0Mar\u00edtimo y Portuario dentro de los cinco (5) d\u00edas siguientes a su presentaci\u00f3n \u00a0acompa\u00f1ada de un concepto sobre la conveniencia y necesidad del servicio \u00a0solicitado. La resoluci\u00f3n que resuelva la petici\u00f3n se expedir\u00e1 dentro de los \u00a0quince (15) d\u00edas siguientes a la fecha de recibo de la documentaci\u00f3n en la \u00a0Direcci\u00f3n General Mar\u00edtima y Portuaria. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo \u00a0Cuando la petici\u00f3n se refiera a transporte conjunto de pasajeros y de carga, la \u00a0capitan\u00eda de puerto deber\u00e1 remitir con la documentaci\u00f3n los resultados de la \u00a0inspecci\u00f3n de que trata el art\u00edculo 66 del Decreto 2451 de 1986. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Texto inicial: \u201cTRANSPORTE CONJUNTO \u00a0DE CARGA Y PASAJEROS. La Direcci\u00f3n General Mar\u00edtima y Portuaria podr\u00e1 autorizar \u00a0en forma extraordinaria la prestaci\u00f3n del servicio de transporte conjunto de \u00a0carga y pasajeros, cuando el armador interesado demuestre que la nave a \u00a0utilizarse dispone de espacios separados para el adecuado transporte de los \u00a0pasajeros y de la carga y re\u00fane las condiciones de seguridad necesarias. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Para el efecto \u00a0anterior, se practicar\u00e1 una inspecci\u00f3n por la Capitan\u00eda de Puerto respectivo, a \u00a0fin de verificar si esta separaci\u00f3n es lo suficientemente segura y adecuada, si \u00a0la nave cumple con las dem\u00e1s condiciones relativas a la seguridad de la vida humana \u00a0en el mar y si \u00e9sta cuenta con los elementos b\u00e1sicos de comodidad para los \u00a0pasajeros. Concluida la inspecci\u00f3n, el Capit\u00e1n de Puerto fijar\u00e1 el n\u00famero \u00a0m\u00e1ximo de pasajeros que la nave podr\u00e1 transportar en cualquier momento, la \u00a0cantidad m\u00e1xima de carga que podr\u00e1 movilizar conjuntamente con pasajeros, el \u00a0n\u00famero m\u00ednimo de tripulantes y los elementos de seguridad y de comunicaciones \u00a0que deber\u00e1n permanecer siempre a bordo y en estado operativo.\u201d. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 67. CARGA PELIGROSA. \u00a0Queda prohibido el transporte conjunto de pasajeros y de carga peligrosa. Se \u00a0entiende por carga peligrosa aquella clasificada en la regla 2, cap\u00edtulo VII de \u00a0la Ley 8 de 1980. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 68. \u00a0CONOCIMIENTOS DE EMBARQUE. Todos los armadores colombianos que presten el \u00a0servicio p\u00fablico de transporte deber\u00e1n registrar ante la Direcci\u00f3n General \u00a0Mar\u00edtima y Portuaria dentro de los noventa (90) d\u00edas siguientes a la vigencia \u00a0del presente Decreto, el texto o textos que utilicen como formatos de sus \u00a0conocimientos de embarque o documentos de transporte. Si tal formato estuviere \u00a0en lengua extranjera deber\u00e1 acompa\u00f1arse adem\u00e1s la correspondiente traducci\u00f3n \u00a0oficial. No podr\u00e1n utilizarse conocimientos de embarque o documentos de \u00a0transporte sin que previamente se hubieren registrado tales textos o formatos \u00a0en la Direcci\u00f3n General Mar\u00edtima Portuaria. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Cuando un armador \u00a0utilice varios tipos de conocimientos de embarque indicar\u00e1 con claridad al \u00a0momento de su registro, cu\u00e1les utiliza para cada ruta o servicio. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 69. \u00a0PRESCRIPCION. La acci\u00f3n o investigaci\u00f3n por violaci\u00f3n o infracci\u00f3n de \u00a0cualquiera de las normas de Marina Mercante prescribe en el t\u00e9rmino de un (1) \u00a0a\u00f1o, contado a partir de la realizaci\u00f3n del hecho. La iniciaci\u00f3n de la \u00a0investigaci\u00f3n respectiva, siempre que medie notificaci\u00f3n del interesado, \u00a0interrumpe este t\u00e9rmino de prescripci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">La sanci\u00f3n a que \u00a0hubiere lugar prescribir\u00e1 en dos (2) a\u00f1os a partir de la ejecutoria de la \u00a0providencia que la impuso, conforme al art\u00edculo 9 de la Ley 2 de 1984. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 70. FONDEO. \u00a0Para las naves o artefactos navales que se encuentren sometidos al proceso de \u00a0investigaci\u00f3n por accidentes o siniestros mar\u00edtimos, o retenidos a \u00f3rdenes del \u00a0Consejo Nacional de Estupefacientes, las tarifas de fondeo se reducir\u00e1n en un \u00a0ochenta por ciento (80%), desde cuando la nave quede retenida y hasta que se \u00a0levante esta medida, siempre que el armador de dicha nave resulte inocente o no \u00a0culpable del hecho que se investiga. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 71. DIMAR. \u00a0Cuando en este Decreto se usa la expresi\u00f3n &#8220;DIMAR&#8221; o &#8220;Autoridad \u00a0Mar\u00edtima&#8221;, se alude a la Direcci\u00f3n General Mar\u00edtima y Portuaria, \u00a0dependencia del Ministerio de Defensa. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 72. VIGENCIA. \u00a0El presente Decreto empezar\u00e1 a regir a partir de su promulgaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Dado en Bogot\u00e1, D. E., \u00a0a 31 de julio de 1986. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">BELISARIO BETANCUR \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Defensa \u00a0Nacional, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">General MIGUEL VEGA \u00a0URIBE. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Ministro de Obras \u00a0P\u00fablicas y Transporte, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">RODOLFO SEGOVIA SALAS. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO \u00a02451 DE 1986 \u00a0 \u00a0 (julio 31) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Por el cual se reglamentan \u00a0parcialmente el C\u00f3digo de Comercio (Decreto ley 410 de \u00a01971) y el Decreto ley 2324 \u00a0de 1984, sobre Transporte Mar\u00edtimo y se dictan \u00a0otras disposiciones. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Nota 1: \u00a0Derogado por el Decreto 3111 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-18092","post","type-post","status-publish","format-standard","hentry","category-decretos-1986"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/18092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=18092"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/18092\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=18092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=18092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=18092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}