{"id":19839,"date":"2023-07-10T21:56:51","date_gmt":"2023-07-10T21:56:51","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/10\/decreto-2193-de-1989\/"},"modified":"2023-07-10T21:56:51","modified_gmt":"2023-07-10T21:56:51","slug":"decreto-2193-de-1989","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/10\/decreto-2193-de-1989\/","title":{"rendered":"DECRETO 2193 DE 1989"},"content":{"rendered":"\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETO 2193 DE 1989 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">(septiembre 25) \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0por el cual se reorganiza la Academia y Centros \u00a0Docentes del Departamento Administrativo de Seguridad. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0Nota: Adicionado por el Decreto 78 de 2000. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">\u00a0El \u00a0Presidente de la Rep\u00fablica de Colombia, en uso de las facultades \u00a0extraordinarias que le confiere la Ley 43 de 1988, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DECRETA: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">TITULO I \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">PRINCIPIOS GENERALES. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 1\u00b0 NATURALEZA. La Academia Superior de \u00a0Inteligencia y Seguridad P\u00fablica &#8220;Aquimindia&#8221; y las escuelas \u00a0regionales del Departamento Administrativo de Seguridad, dependientes de la \u00a0Subjefatura del Departamento, son centros de naturaleza docente en el campo de \u00a0la seguridad y la investigaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 2\u00b0 OBJETIVOS. Corresponde a la Academia \u00a0Superior de Inteligencia y Seguridad P\u00fablica y a las Escuelas Regionales del \u00a0Departamento Administrativo de Seguridad, formar profesionalmente, \u00a0especializar, capacitar, actualizar y adiestrar al personal de inteligencia \u00a0protecci\u00f3n, investigaci\u00f3n, extranjer\u00eda y administrativo que los servicios del \u00a0Departamento demanden, ci\u00f1\u00e9ndose en lo pertinente a lo dispuesto por el Decreto ley 80 de \u00a01980 y a los que lo adicionen, modifiquen o reformen y a las normas del \u00a0presente Decreto. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">TITULO II \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">FUNCIONES. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 3\u00b0 GENERALES. Son funciones de la Academia \u00a0Superior de Inteligencia y Seguridad P\u00fablica y de las Escuelas Regionales: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Formar \u00e9tica, cient\u00edfica, tecnol\u00f3gica y \u00a0profesionalmente a los aspirantes al cargo de detective y a los dem\u00e1s \u00a0funcionarios del Departamento, seg\u00fan las pol\u00edticas trazadas por la Jefatura del \u00a0Departamento; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Organizar y desarrollar los cursos que se requieran \u00a0para el ingreso o iniciaci\u00f3n en el servicio, para el ascenso, actualizaci\u00f3n y \u00a0adiestramiento de los empleados del Departamento; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Fomentar el bienestar estudiantil y las dem\u00e1s acciones \u00a0que tiendan a mejorar el nivel cultural y t\u00e9cnico del personal docente; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Planear, promover y desarrollar investigaciones \u00a0relacionadas con la misi\u00f3n que legalmente corresponde al Departamento; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Dise\u00f1ar, experimentar, evaluar y difundir m\u00e9todos y \u00a0t\u00e9cnicas para el mejoramiento de los procesos aplicables en el campo de la \u00a0seguridad y la investigaci\u00f3n; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">f) Evaluar los resultados y alcances de la instrucci\u00f3n \u00a0impartida y proponer y ejecutar los mecanismos tendientes a su mejoramiento; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">g) Intercambiar programas, experiencias y tecnolog\u00edas \u00a0con otros centros docentes nacionales o extranjeros; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">h) Organizar y desarrollar, mediante convenios del \u00a0Departamento con otras instituciones, cursos en el campo de la seguridad y la \u00a0investigaci\u00f3n; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">i) Expedir los t\u00edtulos de conformidad con las \u00a0modalidades educativas que se autoricen; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">j) Las que por su naturaleza les correspondan en \u00a0virtud de otras disposiciones legales. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">TITULO III \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">ESTRUCTURA Y FUNCIONES ESPECIFICAS. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO I \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">ESTRUCTURA. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 4\u00b0 ESTRUCTURA B\u00c1SICA. Para el cumplimiento de \u00a0sus funciones legales, la Academia Superior de Inteligencia y Seguridad \u00a0P\u00fablica, y las Escuelas Regionales tienen la siguiente estructura: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">I ACADEMIA SUPERIOR DE INTELIGENCIA Y SEGURIDAD \u00a0P\u00daBLICA &#8220;AQUIMINDIA&#8221;. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Direcci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Subdirecci\u00f3n Acad\u00e9mica. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2.1. Secci\u00f3n de Selecci\u00f3n e Incorporaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2.2. Secci\u00f3n de Estudios. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2.3. Secci\u00f3n Psicopedag\u00f3gica. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3. Subdirecci\u00f3n Administrativa. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3.1. Secci\u00f3n de Personal. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">3.2. Secci\u00f3n de Servicios y Suministros. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">II ESCUELAS REGIONALES. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Direcci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Subdirecci\u00f3n Acad\u00e9mica y Administrativa. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2.1. Secci\u00f3n Acad\u00e9mica. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2.2. Secci\u00f3n Administrativa. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">III UNIDADES DE ESTUDIO Y DECISION DE LA ACADEMIA Y DE \u00a0LAS ESCUELAS REGIONALES. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">1. Comit\u00e9 Interdisciplinario. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">2. Junta de Admisiones. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 5\u00b0 ORGANIZACI\u00d3N INTERNA. El Jefe del \u00a0Departamento organizar\u00e1 el funcionamiento interno de la Direcci\u00f3n y \u00a0Subdirecciones de la Academia de Inteligencia y Seguridad P\u00fablica y de las \u00a0Escuelas Regionales, con base en la estructura se\u00f1alada en este Decreto y en la \u00a0planta de personal fijada por el Gobierno. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Igualmente fijar\u00e1 mediante resoluci\u00f3n las funciones de \u00a0las Subdirecciones y de las Secciones y determinar\u00e1 el funcionamiento de grupos \u00a0de trabajo de planeaci\u00f3n y asesor\u00eda t\u00e9cnica y educativa. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 6\u00b0 ESCUELAS REGIONALES. El Jefe del \u00a0Departamento podr\u00e1, cuando las necesidades del servicio lo exijan, crear, \u00a0fusionar o suprimir las Escuelas Regionales, se\u00f1alar las relaciones de \u00a0subordinaci\u00f3n con las restantes reparticiones y asignarles con base en la respectiva \u00a0planta de personal, los cargos correspondientes. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO II \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">FUNCIONES ESPECIFICAS. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 7\u00b0 FUNCIONES DE LA DIRECCION DE LA ACADEMIA. \u00a0Corresponde a la Direcci\u00f3n de la Academia de Inteligencia y Seguridad P\u00fablica: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Dirigir las actividades docentes y administrativas; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Dise\u00f1ar, elaborar y someter a consideraci\u00f3n del \u00a0Consejo de Academias y Escuelas y del Jefe del Departamento los planes de \u00a0estudio, programas, manuales y dem\u00e1s normas de instrucci\u00f3n relacionadas con la \u00a0formaci\u00f3n intelectual, f\u00edsica, moral y t\u00e9cnica de los educandos; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Dirigir y coordinar los procesos de selecci\u00f3n e \u00a0incorporaci\u00f3n de los alumnos en la Academia; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Elaborar anualmente el anteproyecto de presupuesto \u00a0de la Academia y controlar la ejecuci\u00f3n presupuestal y los registros contables; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Velar por el correcto funcionamiento de la Academia \u00a0en los campos docente, disciplinario, investigativo y administrativo; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">f) Presidir las reuniones del Comit\u00e9 \u00a0Interdisciplinario y de la Junta de Admisiones; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">g) Refrendar los certificados y t\u00edtulos que la \u00a0Academia confiera; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">h) Coordinar con entidades p\u00fablicas y privadas y con \u00a0organismos internacionales el desarrollo de cursos y programas relacionados con \u00a0la capacitaci\u00f3n y especializaci\u00f3n del personal del Departamento; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">i) Proponer al Jefe del Departamento la designaci\u00f3n de \u00a0profesores, previo estudio y comprobaci\u00f3n de su idoneidad moral, profesional y \u00a0docente; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">j) Adoptar las medidas necesarias para el buen \u00a0funcionamiento, orden y disciplina de la Academia, e impartir las \u00f3rdenes e \u00a0instrucciones que contribuyan a garantizar la formaci\u00f3n, capacitaci\u00f3n y \u00a0especializaci\u00f3n de los funcionarios del Departamento; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">k) Las dem\u00e1s que le sean asignadas por ley, reglamento \u00a0o resoluci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 8\u00b0 FUNCIONES DE LA DIRECCION EN LAS ESCUELAS \u00a0REGIONALES. Corresponde a la Direcci\u00f3n de cada escuela regional: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Dirigir las actividades docentes y administrativas; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Velar por el buen funcionamiento de la escuela en \u00a0los campos docente, disciplinario y administrativo; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Dise\u00f1ar, elaborar y presentar a consideraci\u00f3n del \u00a0Consejo de Academias y Escuelas y del Jefe del Departamento los planes y \u00a0programas correspondientes a los cursos espec\u00edficos que le correspondan; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Dirigir y coordinar los procesos de selecci\u00f3n e \u00a0incorporaci\u00f3n de los alumnos en la escuela; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Desarrollar y aplicar las pol\u00edticas de la jefatura \u00a0del Departamento y de la Direcci\u00f3n de Recursos Humanos sobre aspectos docentes \u00a0especiales; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">f) Presidir las reuniones del Comit\u00e9 \u00a0Interdisciplinario y de la Junta de Admisiones; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">g) Refrendar los certificados y t\u00edtulos que la escuela \u00a0confiera; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">h) Preparar anualmente el anteproyecto de presupuesto \u00a0de la escuela y solicitar cada mes las partidas indispensables para su \u00a0funcionamiento; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">i) Proponer a la Jefatura del Departamento la designaci\u00f3n \u00a0o remoci\u00f3n de profesores y adoptar las medidas necesarias para la conservaci\u00f3n \u00a0del orden y la disciplina internos; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">j) Las dem\u00e1s que les sean asignadas por reglamento o \u00a0resoluci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">CAPITULO lll \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">UNIDADES DE ESTUDIO Y DECISI\u00d3N. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 9\u00b0 COMITE INTERDISCIPLINARIO. El Comit\u00e9 \u00a0Interdisciplinario est\u00e1 integrado por: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) El Director de la Academia o de la escuela \u00a0regional, quien lo preside; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) El Subdirector Acad\u00e9mico; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) El Jefe de la Secci\u00f3n de Estudios o el de la \u00a0Secci\u00f3n Acad\u00e9mica; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Dos (2) profesores y un (1) alumno designados por \u00a0el Director respectivo. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Actuar\u00e1 como Secretario un (1) Jefe de Secci\u00f3n \u00a0designado por el propio Comit\u00e9. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 10. FUNCIONES DEL COMITE INTERDISCIPLINARIO. \u00a0Corresponde al Comit\u00e9 Interdisciplinario: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Preparar los proyectos, planes y programas que \u00a0deban ser sometidos a consideraci\u00f3n del Consejo de Academias y Escuelas; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Examinar peri\u00f3dicamente la marcha del centro \u00a0docente, recomendar los correctivos o medidas necesarias para la soluci\u00f3n de \u00a0los problemas acad\u00e9micos y rendir informe a las Subjefaturas del Departamento; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Evaluar el desarrollo de los programas acad\u00e9micos y \u00a0vigilar la ejecuci\u00f3n de las pol\u00edticas educativas adoptadas; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Proponer a la Direcci\u00f3n el otorgamiento de \u00a0est\u00edmulos a los alumnos y profesores que sobresalgan por sus m\u00e9ritos, \u00a0eficiencia, honestidad y disciplina, con arreglo a las disposiciones vigentes; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Conceptuar sobre el rendimiento, conducta y \u00a0disciplina de los alumnos para su ingreso al servicio en per\u00edodo de prueba; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">f) Emitir concepto en los asuntos que el Director \u00a0someta a su consideraci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 11. JUNTA DE ADMISIONES. La Junta de \u00a0Admisiones est\u00e1 integrada por: el Director, quien la preside; el Subdirector \u00a0Acad\u00e9mico, el Jefe de la Secci\u00f3n de Selecci\u00f3n e Incorporaci\u00f3n o el de la \u00a0Secci\u00f3n Acad\u00e9mica, dos (2) profesionales administrativos designados por el \u00a0Director. Actuar\u00e1 como Secretario el Jefe de la Secci\u00f3n Psicopedag\u00f3gica o el de \u00a0la Secci\u00f3n Acad\u00e9mica. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 12. FUNCIONES DE LA JUNTA DE ADMISIONES. \u00a0Corresponde a la Junta de Admisiones: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Fijar los criterios, determinar las pruebas y \u00a0se\u00f1alar los requisitos que deben tenerse en cuenta para la selecci\u00f3n de \u00a0aspirantes a los diversos cursos; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Estudiar las condiciones individuales de los \u00a0aspirantes y recomendar la admisi\u00f3n de quienes hayan reunido los requisitos \u00a0correspondientes; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Examinar las solicitudes y reclamos que se \u00a0presenten y proponer las decisiones pertinentes. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">TITULO IV \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">INGRESO Y CURSOS. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 13. REQUISITOS DE INGRESO. Para ingresar como \u00a0alumno al curso de formaci\u00f3n b\u00e1sica de detective, adem\u00e1s de las normas \u00a0generales que sobre administraci\u00f3n de personal, rigen para los empleados del \u00a0Departamento Administrativo de Seguridad, son requisitos especiales: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Ser colombiano de nacimiento; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Ser ciudadano en ejercicio menor de veintis\u00e9is (26) \u00a0a\u00f1os; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) No registrar antecedentes penales ni de polic\u00eda; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) No haber sido separado por mala conducta o \u00a0destituido de las Fuerzas Militares, de la Polic\u00eda Nacional o de cualquier \u00a0cargo p\u00fablico; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Tener definida la situaci\u00f3n militar; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">f) Ser soltero y mantenerse en el mismo estado durante \u00a0su permanencia en el respectivo centro docente; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">g) Aprobar los ex\u00e1menes de aptitud psicof\u00edsica \u00a0practicados por la Divisi\u00f3n de Sanidad del Departamento y la Caja Nacional de \u00a0Previsi\u00f3n; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">h) Ser bachiller y aprobar los ex\u00e1menes practicados \u00a0por el Instituto Colombiano para el Fomento de la Educaci\u00f3n Superior (ICFES) \u00a0con el puntaje m\u00ednimo se\u00f1alado en la respectiva resoluci\u00f3n expedida por el DAS; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">i) Alcanzar el puntaje requerido, con arreglo a las \u00a0bases del curso, en los ex\u00e1menes de admisi\u00f3n y en las entrevistas personales y \u00a0familiares; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">j) Ser seleccionado por la Junta de Admisiones. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">k) Adicionado por el Decreto 78 de 2000, \u00a0art\u00edculo 3\u00ba. Afiliaci\u00f3n a una Empresa Promotora de Salud (EPS) o \u00a0constituci\u00f3n de una P\u00f3liza de Seguros de Servicios M\u00e9dico-quir\u00fargicos, la que \u00a0deber\u00e1 mantenerse vigente durante el per\u00edodo de formaci\u00f3n; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">l) Adicionado por el Decreto 78 de 2000, \u00a0art\u00f3cilo 3\u00ba. Constituci\u00f3n de una P\u00f3liza de Seguros de Vida e Invalidez, que \u00a0deber\u00e1 mantenerse vigente durante el per\u00edodo de formaci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 14. PROCESO DE SELECCI\u00d3N. La Academia y las \u00a0escuelas regionales adelantar\u00e1n el siguiente proceso para la selecci\u00f3n de los \u00a0alumnos: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Propaganda y divulgaci\u00f3n; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Inscripci\u00f3n; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Pruebas, ex\u00e1menes y presentaci\u00f3n de \u00a0certificaciones; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Evaluaci\u00f3n de documentos y cita para entrevista \u00a0personal; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Entrevistas, visitas domiciliarias y estudio de \u00a0seguridad; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">f) Concepto favorable de la Junta de Admisiones del \u00a0respectivo Centro Docente. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. El Jefe del Departamento, mediante \u00a0resoluci\u00f3n, determinar\u00e1 las bases, caracter\u00edsticas y condiciones de las \u00a0diversas etapas del proceso de selecci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 16. INGRESO DE FUNCIONARIOS P\u00daBLICOS \u00a0NACIONALES O EXTRANJEROS. Previo convenio del Departamento con entidades \u00a0p\u00fablicas nacionales o con gobiernos extranjeros, podr\u00e1n ingresar a la Academia \u00a0Superior de Inteligencia y Seguridad P\u00fablica o a las Escuelas Regionales los \u00a0funcionarios nacionales o extranjeros que requieran formaci\u00f3n b\u00e1sica o \u00a0especializada como detectives o criminal\u00edsticos. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 17. CLASES DE CURSOS. En la Academia y en las \u00a0Escuelas Regionales del Departamento se programar\u00e1n y dictar\u00e1n los siguientes \u00a0cursos para el \u00e1rea operativa: \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">a) Inducci\u00f3n; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">b) Formaci\u00f3n b\u00e1sica; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">c) Especializaci\u00f3n; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">d) Capacitaci\u00f3n para ascenso; \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">e) Actualizaci\u00f3n, y \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">f) Adiestramiento. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Para las \u00e1reas de Direcci\u00f3n Superior y Administrativa \u00a0se programar\u00e1n y dictar\u00e1n los cursos de inducci\u00f3n para iniciarse en el servicio \u00a0y los de actualizaci\u00f3n y adiestramiento. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Par\u00e1grafo. En la Academia y en las Escuelas Regionales \u00a0se podr\u00e1n adelantar seminarios, cursillos, ciclos de conferencias y otras \u00a0actividades relacionadas con la formaci\u00f3n cultural y la ense\u00f1anza de t\u00e9cnicas \u00a0de investigaci\u00f3n y administraci\u00f3n. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 18. CURSO DE INDUCCI\u00d3N. El curso de inducci\u00f3n \u00a0para los funcionarios del Area Operativa, exceptuados los detectives, es \u00a0obligatorio antes de tomar posesi\u00f3n de los cargos para los cuales han sido \u00a0nombrados. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El curso de inducci\u00f3n para los funcionarios del Area \u00a0de Direcci\u00f3n Superior y del Area Administrativa es obligatorio despu\u00e9s de su \u00a0posesi\u00f3n en los cargos y antes de la iniciaci\u00f3n en el servicio. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 19. CURSO DE FORMACI\u00d3N B\u00c1SICA. El curso de \u00a0formaci\u00f3n b\u00e1sica es obligatorio para los aspirantes al cargo de detective y \u00a0tendr\u00e1 una duraci\u00f3n m\u00ednima de seis (6) meses. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 20. CURSO DE ESPECIALIZACI\u00d3N. Finalizado el \u00a0curso de formaci\u00f3n b\u00e1sica, seg\u00fan las necesidades del servicio, los aspirantes \u00a0al cargo de detective seguir\u00e1n cursos de especializaci\u00f3n en materia de \u00a0inteligencia protecci\u00f3n, investigaci\u00f3n y seguridad rural, dactiloscopia y \u00a0extranjer\u00eda, cuya duraci\u00f3n no ser\u00e1 inferior a cuatro (4) meses. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 21. INTERNADO. Durante el t\u00e9rmino de duraci\u00f3n \u00a0de los cursos de formaci\u00f3n b\u00e1sica y especializaci\u00f3n para los aspirantes a los \u00a0cargos de detective, los alumnos de Academia permanecer\u00e1n internos en el \u00a0respectivo centro docente, si as\u00ed lo dispone la Jefatura del Departamento. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 22. CURSOS DE CAPACITACI\u00d3N PARA ASCENSO. Los \u00a0cursos de capacitaci\u00f3n para ascenso se programar\u00e1n y dictar\u00e1n a los detectives \u00a0para la provisi\u00f3n de los cargos vacantes en el r\u00e9gimen especial de carrera. Su \u00a0duraci\u00f3n m\u00ednima ser\u00e1 de un (1) mes. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 23. CURSOS DE ACTUALIZACI\u00d3N Y ADIESTRAMIENTO. \u00a0La Jefatura del Departamento, previo estudio de la Direcci\u00f3n de Recursos \u00a0Humanos y concepto del Consejo de Academias y Escuelas, podr\u00e1 disponer la \u00a0realizaci\u00f3n de cursos de actualizaci\u00f3n y adiestramiento en las disciplinas \u00a0necesarias para mejorar el nivel profesional t\u00e9cnico y administrativo del \u00a0personal de empleados del Departamento Administrativo de Seguridad. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 24. CURSOS PARA CRIMINALISTICOS. Para la \u00a0provisi\u00f3n de cargos de criminal\u00edsticos, la Jefatura del Departamento, previo \u00a0estudio de la Direcci\u00f3n de Recursos Humanos y concepto del Consejo de Academias \u00a0y Escuelas, podr\u00e1 disponer la realizaci\u00f3n de cursos de formaci\u00f3n y \u00a0especializaci\u00f3n para los empleados del Departamento. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 25. T\u00cdTULOS OTORGADOS. Los t\u00edtulos que expidan \u00a0la Academia y Escuelas Regionales del Departamento Administrativo de Seguridad \u00a0a quienes hubieren hecho los cursos de formaci\u00f3n b\u00e1sica y de especializaci\u00f3n, y \u00a0las certificaciones, constancias, y diplomas correspondientes a los dem\u00e1s \u00a0cursos, tendr\u00e1n la naturaleza y validez que autorice el Instituto Colombiano \u00a0para el Fomento de la Educaci\u00f3n Superior, previos los tr\u00e1mites legales \u00a0pertinentes. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">TITULO V \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">DISPOSICIONES GENERALES. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 26. ASESORIA EN CAPACITACI\u00d3N. El Departamento \u00a0Administrativo del Servicio Civil, prestar\u00e1 la asesor\u00eda que en materia de \u00a0capacitaci\u00f3n le solicite el Departamento Administrativo de Seguridad. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 27. FUNCIONAMIENTO DE LA ACADEMIA Y DE LAS \u00a0ESCUELAS. El Jefe del Departamento Administrativo de Seguridad, mediante \u00a0resoluci\u00f3n, establecer\u00e1 los mecanismos necesarios para el adecuado \u00a0funcionamiento de la Academia y de las Escuelas Regionales, los planes de \u00a0estudio, los sistemas de calificaci\u00f3n, la duraci\u00f3n de los cursos, intensidad de \u00a0las materias, asistencia a clases, evaluaciones, reclamaciones, habilitaciones \u00a0y todo lo relacionado con el profesorado, as\u00ed como los dem\u00e1s aspectos de la \u00a0docencia en los cursos y sobre las \u00e1reas que a ellas competen. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Art\u00edculo 28. VIGENCIA. Este Decreto rige desde la \u00a0fecha de su publicaci\u00f3n en el DIARIO OFICIAL y deroga las disposiciones que le \u00a0sean contrarias, en especial el Decreto 1550 de 1978. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Comun\u00edquese, publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Dado en \u00a0Bogot\u00e1, D. E., a 25 de septiembre de 1989. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">VIRGILIO BARCO \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Jefe \u00a0del Departamento Administrativo del Servicio Civil, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">WILLIAM RENE PARRA GUTIERREZ. \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">El Jefe \u00a0del Departamento Administrativo de Seguridad, \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">Brigadier General MIGUEL A. MAZA M\u00c1RQUEZ. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 2193 DE 1989 \u00a0 \u00a0 \u00a0 \u00a0 (septiembre 25) \u00a0 \u00a0 \u00a0por el cual se reorganiza la Academia y Centros \u00a0Docentes del Departamento Administrativo de Seguridad. \u00a0 \u00a0 \u00a0Nota: Adicionado por el Decreto 78 de 2000. \u00a0 \u00a0 \u00a0El \u00a0Presidente de la Rep\u00fablica de Colombia, en uso de las facultades \u00a0extraordinarias que le confiere [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-19839","post","type-post","status-publish","format-standard","hentry","category-decretos-1989"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/19839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=19839"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/19839\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=19839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=19839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=19839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}