{"id":30084,"date":"2023-07-18T21:49:57","date_gmt":"2023-07-18T21:49:57","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/18\/decreto-2107-de-2001\/"},"modified":"2023-07-18T21:49:57","modified_gmt":"2023-07-18T21:49:57","slug":"decreto-2107-de-2001","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/18\/decreto-2107-de-2001\/","title":{"rendered":"DECRETO 2107 DE 2001"},"content":{"rendered":"\n<p>DECRETO 2107 DE 2001 \u00a0 \u00a0<\/p>\n<p>(octubre 8) \u00a0 \u00a0<\/p>\n<p>por el cual se dictan \u00a0disposiciones sobre la expedici\u00f3n de visas, control y regularizaci\u00f3n de \u00a0extranjeros y se dictan otras disposiciones en materia de inmigraci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Nota 1: Derogado parcialmente por el Decreto 4000 de 2004. \u00a0 \u00a0<\/p>\n<p>Nota 2: \u00a0Modificado por el Decreto 3521 de 2003, el Decreto 1384 de 2002, \u00a0el Decreto 367 de 2002 \u00a0y por el Decreto 342 de 2002. \u00a0 \u00a0<\/p>\n<p>Nota 3: Ver Decreto 2622 de 2009, \u00a0art\u00edculo 21. \u00a0 \u00a0<\/p>\n<p>Nota: Citado en la Revista de la Universidad de Medell\u00edn. Opini\u00f3n \u00a0Jur\u00eddica. Vol. 11. No. 21. El sistema colombiano de migraciones a la \u00a0luz del derecho internacional de los derechos humanos: la Ley 1465 de 2011 y \u00a0sus antecedentes normativos. Mar\u00eda Teresa Palacios Sanabria. \u00a0 \u00a0<\/p>\n<p>El Presidente de la \u00a0Rep\u00fablica de Colombia, en ejercicio de la facultad que le confiere el art\u00edculo \u00a0189, numeral 2\u00ba de la Constituci\u00f3n Pol\u00edtica, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00ba. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Es competencia discrecional del Gobierno Nacional, fundado en el principio \u00a0de la soberan\u00eda del Estado, autorizar el ingreso de extranjeros al pa\u00eds y su \u00a0permanencia. \u00a0 \u00a0<\/p>\n<p>Corresponde al Ministerio de Relaciones Exteriores, a trav\u00e9s de la \u00a0Direcci\u00f3n del Protocolo, del Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine, de las Misiones Diplom\u00e1ticas y Oficinas \u00a0Consulares, seg\u00fan el caso, otorgar, negar o cancelar visas. \u00a0 \u00a0<\/p>\n<p>Sin perjuicio de lo dispuesto en los Tratados Internacionales, el \u00a0ingreso de extranjeros, as\u00ed como su permanencia o salida del territorio \u00a0nacional, se regir\u00e1n por las disposiciones de este decreto y por las pol\u00edticas \u00a0del Gobierno Nacional. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00ba. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Son extranjeros quienes no re\u00fanen las condiciones para ser \u00a0nacionales colombianos, de acuerdo con la Constituci\u00f3n Pol\u00edtica de Colombia. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00ba. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Ministerio de Relaciones Exteriores fijar\u00e1 la pol\u00edtica \u00a0migratoria y se crear\u00e1 la Comisi\u00f3n Nacional de Migraci\u00f3n como \u00f3rgano asesor del \u00a0Gobierno Nacional en la coordinaci\u00f3n de la misma. \u00a0 \u00a0<\/p>\n<p>TITULO I \u00a0 \u00a0<\/p>\n<p>INMIGRACION \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 4\u00ba. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La planeaci\u00f3n de la inmigraci\u00f3n tendr\u00e1 en cuenta los planes de \u00a0desarrollo e inversi\u00f3n globales o sectoriales, p\u00fablicos o privados, para \u00a0determinar las actividades, las profesiones, las zonas de instalaci\u00f3n, los \u00a0aportes de capital y de otro orden que deban efectuar los extranjeros, cuando \u00a0se considere conveniente su admisi\u00f3n al pa\u00eds a trav\u00e9s de programas de \u00a0inmigraci\u00f3n planificada. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 5\u00ba. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La inmigraci\u00f3n se regular\u00e1 de acuerdo con las necesidades sociales, \u00a0demogr\u00e1ficas, econ\u00f3micas, cient\u00edficas, culturales, de seguridad, de orden \u00a0p\u00fablico, sanitarias y dem\u00e1s de inter\u00e9s para el Estado colombiano. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 6\u00ba. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Preferentemente se fomentar\u00e1 el ingreso de inmigrantes en los \u00a0siguientes casos: \u00a0 \u00a0<\/p>\n<p>1. Cuando se trate de personas que por su experiencia, su \u00a0calificaci\u00f3n t\u00e9cnica, profesional o intelectual, contribuyan al desarrollo de \u00a0actividades econ\u00f3micas, cient\u00edficas, culturales o educativas de utilidad o \u00a0beneficio para el pa\u00eds o que se incorporen a actividades o programas de \u00a0desarrollo econ\u00f3mico o de cooperaci\u00f3n internacional definidos por el Gobierno \u00a0Nacional, para cuya ejecuci\u00f3n no se cuente con nacionales capacitados en el \u00a0pa\u00eds o sean insuficientes para satisfacer la demanda. \u00a0 \u00a0<\/p>\n<p>2. Cuando aporten capitales para ser invertidos en el \u00a0establecimiento de empresas de inter\u00e9s para el pa\u00eds o en actividades \u00a0productivas que generen empleo, incrementen o diversifiquen las exportaciones \u00a0de bienes y servicios, en concordancia con las normas aplicables en estas \u00a0materias. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 7\u00ba. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Sin perjuicio de lo expresado en los art\u00edculos anteriores, la \u00a0planeaci\u00f3n y regulaci\u00f3n inmigratoria evitar\u00e1: \u00a0 \u00a0<\/p>\n<p>1. El ingreso y la permanencia de extranjeros que comprometan el \u00a0empleo de trabajadores nacionales, o que por su cantidad y distribuci\u00f3n en el \u00a0territorio nacional configuren un problema con implicaciones pol\u00edticas, \u00a0econ\u00f3micas, sociales o de seguridad que afecten al Estado colombiano. \u00a0 \u00a0<\/p>\n<p>2. El ingreso y permanencia irregular de extranjeros. \u00a0 \u00a0<\/p>\n<p>TITULO II \u00a0 \u00a0<\/p>\n<p>CAPITULO I \u00a0 \u00a0<\/p>\n<p>Disposiciones generales \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 8\u00ba. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para efectos del presente decreto, se entiende por visa la \u00a0autorizaci\u00f3n concedida a un extranjero para el ingreso y permanencia en el \u00a0territorio nacional otorgada por el Ministerio de Relaciones Exteriores, a \u00a0trav\u00e9s de la Direcci\u00f3n del Protocolo, del Grupo Interno de Trabajo que el \u00a0Ministro de Relaciones Exteriores determine, de las Misiones Diplom\u00e1ticas o de \u00a0las Oficinas Consulares, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>El C\u00f3nsul ad honorem debidamente facultado por resoluci\u00f3n del \u00a0Ministerio de Relaciones Exteriores, podr\u00e1 otorgar visas. Para cada caso, \u00a0deber\u00e1 solicitar autorizaci\u00f3n del Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 9\u00ba. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Departamento Administrativo de Seguridad, DAS, podr\u00e1 otorgar al \u00a0extranjero permiso de ingreso y permanencia en el territorio nacional en los \u00a0casos en que no se requiera visa de conformidad con este decreto y seg\u00fan lo \u00a0se\u00f1alado por resoluci\u00f3n del Ministerio de Relaciones Exteriores. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 10. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Ministerio de Relaciones Exteriores podr\u00e1, mediante acto \u00a0administrativo, ampliar o limitar la facultad concedida a las Misiones \u00a0Diplom\u00e1ticas y a las Oficinas Consulares para expedir visas. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 11. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La autorizaci\u00f3n para expedir una visa en el exterior tendr\u00e1 una \u00a0vigencia de hasta tres (3) meses. Vencido este plazo, caducar\u00e1 la autorizaci\u00f3n \u00a0y se archivar\u00e1 la solicitud con la respectiva documentaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 12. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para efectos del presente decreto, se entender\u00e1 por a\u00f1o calendario \u00a0el per\u00edodo de trescientos sesenta y cinco (365) d\u00edas calendario, contados a \u00a0partir del d\u00eda y mes del a\u00f1o de expedici\u00f3n de una visa o del permiso de ingreso \u00a0y permanencia. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 13. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La vigencia de la visa se contar\u00e1 a partir de la fecha de su \u00a0expedici\u00f3n. \u00a0 \u00a0<\/p>\n<p>La vigencia de una visa termina \u00a0en los siguientes casos:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0<\/p>\n<p>1. Por vencimiento del t\u00e9rmino autorizado, contenido en la misma. \u00a0 \u00a0<\/p>\n<p>2. Por orden de autoridad judicial. \u00a0 \u00a0<\/p>\n<p>3. Por caducidad: \u00a0 \u00a0<\/p>\n<p>a) En los casos expresamente contemplados en los art\u00edculos 41, \u00a0par\u00e1grafo del 48, 51 y 85 del presente Decreto; \u00a0 \u00a0<\/p>\n<p>b) Por expedici\u00f3n de una nueva visa; \u00a0 \u00a0<\/p>\n<p>c) A solicitud escrita del titular de la visa; \u00a0 \u00a0<\/p>\n<p>d) Por requerimiento escrito de la persona natural o jur\u00eddica, de \u00a0derecho p\u00fablico o privado que solicit\u00f3 la expedici\u00f3n de la visa para el \u00a0extranjero; \u00a0 \u00a0<\/p>\n<p>e) Por terminaci\u00f3n de la actividad autorizada en la visa, salvo lo \u00a0dispuesto en el art\u00edculo 152 del presente decreto; \u00a0 \u00a0<\/p>\n<p>f) Por cambio de empleador; \u00a0 \u00a0<\/p>\n<p>g) Si las condiciones en virtud de las cuales el extranjero obtuvo \u00a0su visa, se modifican o se extinguen. \u00a0 \u00a0<\/p>\n<p>h) Cuando por error de la Administraci\u00f3n o por causas ajenas a la \u00a0voluntad del solicitante se hubiere expedido una visa sin el cumplimiento de \u00a0alg\u00fan requisito legal, lo cual deber\u00e1 ser informado previamente al interesado. \u00a0 \u00a0<\/p>\n<p>4. Por cancelaci\u00f3n de la visa. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo primero. La caducidad se entender\u00e1 sin necesidad de \u00a0emitir auto o providencia que la ordene. De este hecho se dejar\u00e1 constancia \u00a0escrita en el respectivo expediente y\/o sobre la visa por el Jefe del Grupo \u00a0Interno de Trabajo que el Ministro de Relaciones Exteriores determine. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo segundo. Ocurrida la caducidad, el extranjero podr\u00e1 \u00a0solicitar nueva visa sin necesidad de salir del territorio nacional, ni obtener \u00a0salvoconducto, de acuerdo con las nuevas circunstancias, dentro de los treinta \u00a0(30) d\u00edas siguientes a la ocurrencia del hecho. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo tercero. El Ministerio de Relaciones Exteriores, en uso \u00a0de su competencia soberana y discrecional, a trav\u00e9s del Jefe del Grupo Interno \u00a0de Trab ajo que el Ministro de Relaciones Exteriores \u00a0determine podr\u00e1 disponer, mediante Auto, la cancelaci\u00f3n de la visa. Contra esta \u00a0providencia no procede recurso alguno. \u00a0 \u00a0<\/p>\n<p>Una vez notificado el Auto de cancelaci\u00f3n de la visa, el extranjero \u00a0deber\u00e1 abandonar el pa\u00eds dentro de los treinta (30) d\u00edas calendario siguientes, \u00a0so pena de ser deportado y previa la expedici\u00f3n de un salvoconducto por parte \u00a0del Departamento Administrativo de Seguridad, DAS, en concordancia con lo preceptuado \u00a0en el par\u00e1grafo del art\u00edculo 140 del presente decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 14. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El titular de visa que desee prorrogar su permanencia en el \u00a0territorio nacional, previo cumplimiento de los requisitos, deber\u00e1 solicitar la \u00a0nueva visa ante el Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine o ante las Oficinas Consulares de la Rep\u00fablica, por lo \u00a0menos dentro de los treinta (30) d\u00edas anteriores al vencimiento de la misma, \u00a0salvo fuerza mayor o caso fortuito debidamente comprobados. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo primero. En \u00a0todo caso, el extranjero podr\u00e1 solicitar nueva visa en las Oficinas Consulares, \u00a0en cualquier tiempo. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo segundo. No \u00a0podr\u00e1 solicitar visa en el territorio nacional el extranjero que se encuentre \u00a0en permanencia irregular de acuerdo con lo establecido en el art\u00edculo 110 o que \u00a0est\u00e9 incurso en alguna de las causales establecidas en el art\u00edculo 109 del \u00a0presente decreto, salvo que se trate de la regularizaci\u00f3n establecida en el \u00a0art\u00edculo 163 del mismo o cuando as\u00ed lo determine el Gobierno Nacional. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 15. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La visa otorgada al extranjero, cualquiera que fuese su clase o \u00a0categor\u00eda, no supone la admisi\u00f3n incondicional de \u00e9ste al territorio nacional, \u00a0si se encuentra incurso en alguna de las causales de inadmisi\u00f3n \u00a0o rechazo previstas en el presente decreto. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Cuando \u00a0por razones de seguridad o de orden p\u00fablico as\u00ed lo determine el Ministerio del \u00a0Interior y el Departamento Administrativo de Seguridad, el extranjero deber\u00e1 \u00a0obtener permiso de esta \u00faltima entidad, para ingresar, transitar o permanecer \u00a0en determinadas zonas del territorio de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 16. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La visa al ser expedida, ser\u00e1 identificada con el c\u00f3digo \u00a0correspondiente establecido en el art\u00edculo 28 del presente decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 17. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Modificado por el Decreto 3521 de 2003, \u00a0art\u00edculo 4\u00ba. El extranjero que solicite Visa de Negocios o Temporal por primera \u00a0vez, o de Residente Calificado o Inversionista, adem\u00e1s de los requisitos \u00a0se\u00f1alados en los art\u00edculos 22, 43, 55, 57, 59, 63, 74, 89 y 90, deber\u00e1 \u00a0presentar el Certificado de Antecedentes Judiciales o de Polic\u00eda, expedido por \u00a0la autoridad competente de su pa\u00eds de origen o del \u00faltimo pa\u00eds de residencia, \u00a0seg\u00fan el caso, con una antelaci\u00f3n no superior a seis (6) meses. \u00a0 \u00a0<\/p>\n<p>Se except\u00faa de esta exigencia al solicitante de Visa: Preferencial; \u00a0Cortes\u00eda, salvo los casos establecidos en normas especiales; Inmigrante; \u00a0Tripulante; Temporal Estudiante; Empresarial; Refugiado o Asilado; Visitante y \u00a0Residente como familiar de nacional colombi ano. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. En los \u00a0pa\u00edses en los cuales no se expida este certificado, el Grupo Interno de Trabajo \u00a0que el Ministro de Relaciones Exteriores determine, solicitar\u00e1 a la Interpol la informaci\u00f3n correspondiente. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 18. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero titular de Visa, cualquiera que sea la clase o \u00a0categor\u00eda, podr\u00e1 adelantar estudios en el pa\u00eds. As\u00ed mismo, podr\u00e1 desarrollar \u00a0actividades no remuneradas de car\u00e1cter acad\u00e9mico o de capacitaci\u00f3n inherentes a \u00a0su ocupaci\u00f3n u objeto de la empresa donde labora. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 19. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para efectos del presente decreto, se podr\u00e1 considerar que tiene \u00a0domicilio en Colombia el extranjero titular de Visa de Residente. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 20. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Contra el acto administrativo que niegue el otorgamiento o cancele \u00a0una visa no procede recurso alguno. \u00a0 \u00a0<\/p>\n<p>CAPITULO II \u00a0 \u00a0<\/p>\n<p>De la solicitud de visa \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 21. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La solicitud de visa deber\u00e1 ser tramitada directamente por el \u00a0extranjero o por la entidad o empresa donde presta sus servicios, est\u00e1 vinculado \u00a0o lo patrocina o por su representante legal. En todo caso, el formulario de \u00a0solicitud deber\u00e1 estar firmado por el extranjero solicitante. \u00a0 \u00a0<\/p>\n<p>Cuando la solicitud sea presentada por una persona diferente al \u00a0extranjero, s\u00f3lo se aceptar\u00e1 una solicitud por tr\u00e1mite, salvo cuando se trate \u00a0de grupos familiares o tripulantes. \u00a0 \u00a0<\/p>\n<p>Cuando se trate de grupos art\u00edsticos, culturales o deportivos, la \u00a0solicitud podr\u00e1 ser tramitada por quien haya suscrito el respectivo contrato \u00a0como su representante o apoderado. Para efectos de la representaci\u00f3n de \u00a0incapaces se aplicar\u00e1n las disposiciones legales vigentes. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 22. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El solicitante de visa deber\u00e1: \u00a0 \u00a0<\/p>\n<p>1. Presentar su pasaporte con vigencia m\u00ednima de tres (3) meses, en \u00a0buen estado, con hojas en blanco y fotocopia de las p\u00e1ginas usadas del mismo o \u00a0documento de viaje v\u00e1lido, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>2. Diligenciar correctamente el formulario de solicitud. \u00a0 \u00a0<\/p>\n<p>3. Anexar los requisitos para la visa que solicita, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>4. Anexar tres (3) fotograf\u00edas recientes, de frente, a color, fondo \u00a0claro, de 3 x 3, o seg\u00fan lo determine el Ministerio de Relaciones Exteriores. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo primero. El \u00a0Ministro de Relaciones Exteriores queda facultado para modificar, adicionar o \u00a0aclarar mediante resoluci\u00f3n los requisitos de que trata el presente art\u00edculo. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo segundo. \u00a0Cualquier inexactitud en los datos contenidos en la solicitud ser\u00e1 causal de \u00a0rechazo, negaci\u00f3n o cancelaci\u00f3n de la visa o inadmisi\u00f3n \u00a0al territorio nacional, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo tercero. Los \u00a0certificados de antecedentes judiciales, registros civiles de nacimiento y de \u00a0matrimonio, diplomas y certificados de estudio, expedidos en el exterior, \u00a0deber\u00e1n ser debidamente traducidos al castellano, autenticados ante el \u00a0respectivo funcionario consular de la Rep\u00fablica y legalizados ante el \u00a0Ministerio de Relaciones Exteriores, de conformidad con lo establecido por las \u00a0normas del C\u00f3digo de Procedimiento Civil o apostillados cuando corresponda. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo cuarto. Se \u00a0except\u00faa del cumplimiento de lo dispuesto en este art\u00edculo la expedici\u00f3n de la \u00a0Visa Preferencial, la cual se regir\u00e1 por lo dispuesto en el Cap\u00edtulo I del \u00a0T\u00edtulo III del presente decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 23. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Sin perjuicio de lo establecido en el art\u00edculo 23 de la \u00a0Constituci\u00f3n Pol\u00edtica de Colombia, cuando una solicitud de visa se presente \u00a0incompleta, se le indicar\u00e1 al peticionario los requisitos que falten, se le \u00a0devolver\u00e1 la documentaci\u00f3n y no se radicar\u00e1 la solicitud. En este caso, el \u00a0extranjero podr\u00e1 pedir un salvoconducto de permanencia ante el DAS para \u00a0solicitar o cambiar su visa, de acuerdo con lo establecido en el numeral 2\u00ba del \u00a0art\u00edculo 120 del presente decreto. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Devuelta \u00a0la documentaci\u00f3n al interesado, el tr\u00e1mite de solicitud del salvoconducto de \u00a0permanencia de que trata este art\u00edculo, deber\u00e1 ser autorizado previamente por \u00a0el Jefe del Grupo Interno de Trabajo que el Ministro de Relaciones Exteriores \u00a0determine. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 24. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La informaci\u00f3n y los documentos presentados para la solicitud de \u00a0una visa, por ser parte del archivo del Ministerio de Relaciones Exteriores, \u00a0tienen car\u00e1cter reservado. Solamente el interesado o la autoridad competente, \u00a0podr\u00e1n solicitar fotocopia o desglose de \u00e9stos. En todo caso, se dejar\u00e1 \u00a0fotocopia en el expediente de los documentos entregados. \u00a0 \u00a0<\/p>\n<p>No habr\u00e1 lugar a desglose de aquellos documentos que fueron \u00a0escaneados por parte del Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine toda vez que se tendr\u00e1 un expediente magn\u00e9tico y s\u00f3lo se \u00a0podr\u00e1 solicitar copia de la imagen almacenada. \u00a0 \u00a0<\/p>\n<p>Cualquier solicitud de informaci\u00f3n por parte de un tercero, sobre \u00a0los expedientes que reposen en el Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine, deber\u00e1 ser autorizada por la Secretar\u00eda \u00a0General, teniendo en cuenta la materia y objeto de la consulta. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 25. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Negada una visa, solamente se podr\u00e1 presentar una nueva solicitud, \u00a0transcurridos seis meses contados a partir de la fecha en que se comunic\u00f3 la \u00a0negativa de la visa, a menos que se presenten nuevos elementos que den lugar a \u00a0recibir la nueva solicitud antes del tiempo mencionado. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 26. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. De la decisi\u00f3n sobre una solicitud de visa, se comunicar\u00e1 al \u00a0interesado solamente en la oficina ante la cual present\u00f3 la solicitud. Cuando \u00a0la decisi\u00f3n corresponda a una solicitud presentada por grupo art\u00edstico, \u00a0cultural o deportivo, la comunicaci\u00f3n se surtir\u00e1 con el representante o \u00a0apoderado y ten dr\u00e1 efectos respecto de sus \u00a0integrantes. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 27. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para todos los efectos, se tendr\u00e1 en cuenta la direcci\u00f3n consignada \u00a0por el interesado en el formulario de solicitud. Si cambia de direcci\u00f3n, deber\u00e1 \u00a0informarlo dentro de los sesenta (60) d\u00edas siguientes al Grupo Interno de \u00a0Trabajo que el Ministro de Relaciones Exteriores determine y al Departamento \u00a0Administrativo de Seguridad, DAS. \u00a0 \u00a0<\/p>\n<p>TITULO III \u00a0 \u00a0<\/p>\n<p>DE LAS CLASES Y CATEGORIAS \u00a0DE VISAS \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 28. Derogado parcialmente por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Las visas que se expiden en virtud de lo establecido en el presente \u00a0decreto son de las siguientes clases y categor\u00edas: \u00a0 \u00a0<\/p>\n<p>CLASES\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 CATEGORIAS\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 CODIGO \u00a0 \u00a0<\/p>\n<p>1. Preferencial \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Diplom\u00e1tica\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 PD \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Oficial\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 PO \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 De Servicio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 PS \u00a0 \u00a0<\/p>\n<p>2. Cortes\u00eda\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 CO \u00a0 \u00a0<\/p>\n<p>3. Negocios\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 NE \u00a0 \u00a0<\/p>\n<p>4. Inmigrante\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 IN \u00a0 \u00a0<\/p>\n<p>5. Tripulante\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 BA \u00a0 \u00a0<\/p>\n<p>6. Temporal \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013Trabajador\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 TT \u00a0 \u00a0<\/p>\n<p>\u2013 C\u00f3nyuge o Compa\u00f1ero (a)\u00a0\u00a0\u00a0\u00a0\u00a0 TC \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Permanente de nacional colombiano \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Padre o madre de nacional colombiano\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 TP \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Religioso\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 TR \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Estudiante\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 TE \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Empresarial\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 TM \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Especial\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 TS \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Visitante\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 TV \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Refugiado o Asilado\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 TA \u00a0 \u00a0<\/p>\n<p>7. Residente \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Como familiar de nacional colombiano\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 RN \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Calificado\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 RC \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u2013 Inversionista\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 RI \u00a0 \u00a0<\/p>\n<p>8. Turismo\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 TU \u00a0 \u00a0<\/p>\n<p>CAPITULO I \u00a0 \u00a0<\/p>\n<p>De la Visa Preferencial \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 29. Son Visas Preferenciales \u00a0las siguientes: Diplom\u00e1tica, Oficial y de Servicio, las cuales se regular\u00e1n \u00a0exclusivamente por lo establecido en el presente Cap\u00edtulo. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0PRIMERA \u00a0 \u00a0<\/p>\n<p>De la Visa Preferencial \u00a0Diplom\u00e1tica \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 30. La Direcci\u00f3n \u00a0del Protocolo del Ministerio de Relaciones Exteriores podr\u00e1 otorgar Visa \u00a0Preferencial Diplom\u00e1tica al agente portador de pasaporte diplom\u00e1tico que venga \u00a0a desempe\u00f1ar un cargo en la respectiva Misi\u00f3n Diplom\u00e1tica, Oficina Consular u \u00a0Organismo Internacional debidamente acreditado ante el Gobierno de Colombia, en \u00a0misi\u00f3n especial encomendada por su Gobierno u Organismo Internacional o al que \u00a0en representaci\u00f3n de su pa\u00eds o de un Organismo Internacional asista a reuniones \u00a0o foros de nivel internacional en nuestro pa\u00eds. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo primero. En casos plenamente justificados, la \u00a0Direcci\u00f3n del Protocolo podr\u00e1 autorizar y expedir Visa Preferencial Diplom\u00e1tica \u00a0al agente diplom\u00e1tico, consular o funcionario internacional, que sin ser \u00a0portador de pasaporte diplom\u00e1tico venga al pa\u00eds a desarrollar actividades \u00a0propias de sus funciones. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo segundo. Ser\u00e1n beneficiarios de la Visa \u00a0Preferencial Diplom\u00e1tica el c\u00f3nyuge o compa\u00f1ero(a) permanente del agente y los \u00a0parientes de \u00e9ste hasta el primer grado de consanguinidad y primero civil que \u00a0convivan con \u00e9l en forma permanente y se encuentren bajo su dependencia \u00a0econ\u00f3mica. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 31. La Visa \u00a0Preferencial Diplom\u00e1tica podr\u00e1 ser expedida de manera provisional en el \u00a0exterior por el Jefe de una Misi\u00f3n Diplom\u00e1tica de la Rep\u00fablica, previa \u00a0solicitud formulada por el respectivo Ministerio de Relaciones Exteriores, \u00a0Organismo Internacional, Misi\u00f3n Diplom\u00e1tica u Oficina Consular, seg\u00fan \u00a0corresponda y tendr\u00e1 una vigencia m\u00e1xima de noventa (90) d\u00edas. En casos \u00a0especiales, la Direcci\u00f3n del Protocolo podr\u00e1 autorizar a las Oficinas \u00a0Consulares para este efecto, con las condiciones se\u00f1aladas. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. En situaciones debidamente \u00a0justificadas, la Direcci\u00f3n del Protocolo podr\u00e1 autorizar al Jefe de una Misi\u00f3n \u00a0Diplom\u00e1tica u Oficina Consular de la Rep\u00fablica para expedir Visa Preferencial \u00a0Diplom\u00e1tica por un periodo hasta de dos (2) a\u00f1os. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 32. Sin \u00a0perjuicio de lo establecido en los Acuerdos celebrados en materia de exenci\u00f3n \u00a0de visado, la Visa Preferencial Diplom\u00e1tica la otorgar\u00e1, en el territorio \u00a0nacional, la Direcci\u00f3n del Protocolo hasta por el t\u00e9rmino de cuatro (4) a\u00f1os, \u00a0renovable en caso necesario, previa solicitud de la Misi\u00f3n Diplom\u00e1tica, de la \u00a0Oficina Consular o del Organismo Internacional respectivo. Una vez finalizada \u00a0la misi\u00f3n, el titular de la visa podr\u00e1 permanecer en el pa\u00eds amparado por la \u00a0misma hasta por un per\u00edodo m\u00e1ximo de sesenta (60) d\u00edas calendario. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0SEGUNDA&lt; \/span&gt; \u00a0 \u00a0<\/p>\n<p>De la Visa Preferencial \u00a0Oficial \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 33. La Visa \u00a0Preferencial Oficial podr\u00e1 ser otorgada por la Direcci\u00f3n del Protocolo del \u00a0Ministerio de Relaciones Exteriores al funcionario extranjero que venga al pa\u00eds \u00a0en desempe\u00f1o de una misi\u00f3n oficial. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 34. La Visa \u00a0Preferencial Oficial podr\u00e1 ser expedida provisionalmente en el exterior por el \u00a0Jefe de una Misi\u00f3n Diplom\u00e1tica de la Rep\u00fablica, previa solicitud formulada por \u00a0el respectivo Ministerio de Relaciones Exteriores o entidad oficial competente, \u00a0Organismo Internacional, Misi\u00f3n Diplom\u00e1tica u Oficina Consular, seg\u00fan \u00a0corresponda y tendr\u00e1 una vigencia provisional de noventa (90) d\u00edas. En casos \u00a0especiales, la Direcci\u00f3n del Protocolo podr\u00e1 autorizar a las Oficinas \u00a0Consulares para este fin, con las condiciones se\u00f1aladas. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. En situaciones plenamente \u00a0justificadas, la Direcci\u00f3n del Protocolo podr\u00e1 autorizar al Jefe de una Misi\u00f3n \u00a0Diplom\u00e1tica u Oficina Consular de la Rep\u00fablica para expedir Visa Preferencial \u00a0Oficial por un per\u00edodo hasta de un (1) a\u00f1o. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 35. La Visa \u00a0Preferencial Oficial la otorgar\u00e1 en el territorio nacional la Direcci\u00f3n del \u00a0Protocolo, de acuerdo con la duraci\u00f3n de la misi\u00f3n hasta por el t\u00e9rmino de \u00a0cuatro (4) a\u00f1os y podr\u00e1 ser renovada por per\u00edodos hasta de dos (2) a\u00f1os, previa \u00a0solicitud de la Misi\u00f3n Diplom\u00e1tica, Oficina Consular o del Organismo \u00a0Internacional respectivo. Una vez terminada la misi\u00f3n oficial, el titular de la \u00a0visa podr\u00e1 permanecer en el pa\u00eds amparado por la misma hasta por treinta (30) \u00a0d\u00edas calendario. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. En casos plenamente justificados, la \u00a0Direcci\u00f3n del Protocolo podr\u00e1 autorizar y expedir Visa Preferencial Oficial al \u00a0c\u00f3nyuge o compa\u00f1ero(a) permanente y a los parientes hasta el primer grado de \u00a0consanguinidad y primero civil del funcionario en misi\u00f3n oficial, que convivan \u00a0en forma permanente con el funcionario y se encuentren bajo su dependencia \u00a0econ\u00f3mica. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0TERCERA \u00a0 \u00a0<\/p>\n<p>De la Visa Preferencial de \u00a0Servicio \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 36. La Visa \u00a0Preferencial de Servicio se otorgar\u00e1 por la Direcci\u00f3n del Protocolo al \u00a0extranjero que venga al pa\u00eds en uno de los siguientes casos: \u00a0 \u00a0<\/p>\n<p>a) En calidad de \u00a0funcionario internacional o experto, dentro del Marco de Tratados Internacionales \u00a0que se encuentren vigentes; \u00a0 \u00a0<\/p>\n<p>b) Como miembro del \u00a0personal administrativo y t\u00e9cnico de una Misi\u00f3n Diplom\u00e1tica, Oficina Consular o \u00a0de un Organismo Internacional o de Cooperaci\u00f3n; \u00a0 \u00a0<\/p>\n<p>c) Como miembro del \u00a0personal de servicio de una Misi\u00f3n Diplom\u00e1tica, Oficina Consular o de un \u00a0Organismo Internacional o de Cooperaci\u00f3n, o como empleado particular de un \u00a0miembro del personal de la misi\u00f3n, siempre y cuando el empleado no tenga \u00a0residencia permanente en el pa\u00eds; \u00a0 \u00a0<\/p>\n<p>d) Para realizar \u00a0actividades consideradas por el Ministerio de Relaciones Exteriores como \u00a0esenciales o prioritarias para el pa\u00eds. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo primero. La Direcci\u00f3n del Protocolo podr\u00e1 \u00a0autorizar y expedir Visa Preferencial de Servicio al c\u00f3nyuge o compa\u00f1ero(a) \u00a0permanente del extranjero que venga al pa\u00eds en las condiciones establecidas en \u00a0el presente art\u00edculo y a los hijos que convivan con \u00e9l en forma permanente y se \u00a0encuentren bajo su dependencia econ\u00f3mica. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo segundo. La Visa Preferencial de Servicio \u00a0podr\u00e1 ser expedida provisionalmente en el exterior, con la debida autorizaci\u00f3n \u00a0de la Direcci\u00f3n del Protocolo, por el Jefe de una Misi\u00f3n Diplom\u00e1tica de la \u00a0Rep\u00fablica, o en casos especiales por las Oficinas Consulares, previa solicitud \u00a0formulada por el respectivo Ministerio de Relaciones Exteriores, Organismo \u00a0Internacional, Misi\u00f3n Diplom\u00e1tica u Oficina Consular, seg\u00fan el caso y tendr\u00e1 \u00a0una vigencia provisional de hasta noventa (90) d\u00edas. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo tercero. Para la aplicaci\u00f3n del literal d) del \u00a0presente art\u00edculo, la Direcci\u00f3n del Protocolo tendr\u00e1 as\u00ed mismo en \u00a0consideraci\u00f3n, aquellas actividades que, en desarrollo de pasados acuerdos, \u00a0contin\u00faan siendo de inter\u00e9s para el pa\u00eds y las solicitudes podr\u00e1n ser \u00a0presentadas por las Entidades ejecutoras. Las personas a quienes se otorgue \u00a0Visa Preferencial de Servicio en virtud de dicho literal, no gozar\u00e1n de \u00a0privilegios e inmunidades. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 37. La Visa Preferencial de Servicio la \u00a0otorgar\u00e1 en el territorio nacional la Direcci\u00f3n del Protocolo, previa solicitud \u00a0formulada por la respectiva Misi\u00f3n Diplom\u00e1tica, Oficina Consular u Organismo \u00a0Internacional y su duraci\u00f3n ser\u00e1 establecida conforme al t\u00e9rmino de la misi\u00f3n, \u00a0el contrato de trabajo o la prestaci\u00f3n de servicios, con vigencia hasta dos (2) \u00a0a\u00f1os, renovable por per\u00edodos iguales. Una vez terminada la misi\u00f3n o el contrato \u00a0o actividad, el titular podr\u00e1 permanecer amparado por la misma visa hasta por \u00a0treinta (30) d\u00edas calendario. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 38. Sin perjuicio de lo dispuesto en los \u00a0Tratados Internacionales, el titular de una Visa Preferencial de Servicio no \u00a0podr\u00e1 percibir salarios u honorarios de entidades colombianas, sean p\u00fablicas o \u00a0privadas. \u00a0 \u00a0<\/p>\n<p>CAPITULO II \u00a0 \u00a0<\/p>\n<p>De la Visa de Cortes\u00eda \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 39. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Sin perjuicio de lo dispuesto en normas especiales, la Visa de \u00a0Cortes\u00eda podr\u00e1 ser expedida por el Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine hasta por el t\u00e9rmino de un (1) a\u00f1o y por las \u00a0Misiones Diplom\u00e1ticas o las Oficinas Consulares hasta por el t\u00e9rmino de noventa \u00a0(90) d\u00edas, para m\u00faltiples entradas, al extranjero que pretenda ingresar al \u00a0territorio nacional, en los siguientes casos: \u00a0 \u00a0<\/p>\n<p>a) En raz\u00f3n de su especial prestancia intelectual, profesional, \u00a0cultural, acad\u00e9mica, cient\u00edfica, pol\u00edtica, empresarial, comercial, social, \u00a0deportiva o art\u00edstica; \u00a0 \u00a0<\/p>\n<p>b) Al que pretenda ingresar en virtud de intercambios, programas o \u00a0actividades relacionadas con las \u00e1reas enunciadas anteriormente y que sean \u00a0patrocinados por entidades o instituciones p\u00fablicas o privadas; \u00a0 \u00a0<\/p>\n<p>c) A los funcionarios, expertos, t\u00e9cnicos o empleados de Organismos \u00a0Internacionales a quienes se haya establecido la expedici\u00f3n de esta visa en \u00a0virtud de un Convenio o Acuerdo Internacional; \u00a0 \u00a0<\/p>\n<p>d) Al extranjero, c\u00f3nyuge o compa\u00f1ero(a) permanente de funcionario \u00a0al servicio del Ministerio de Relaciones Exteriores. \u00a0 \u00a0<\/p>\n<p>e) Al extranjero, nacional de un pa\u00eds con el cual Colombia ha \u00a0suscrito o suscriba alg\u00fan Convenio, Acuerdo o Canje de Notas referente a \u00a0facilitaci\u00f3n migratoria para empresarios, representantes legales, directivos, \u00a0ejecutivos u hombres de negocios; \u00a0 \u00a0<\/p>\n<p>f) A los estudiantes, practicantes, docentes y asistentes de \u00a0idiomas que ingresen al pa\u00eds en virtud de Acuerdos de Cooperaci\u00f3n suscritos por \u00a0el Gobierno de Colombia con otros pa\u00edses o promovidos por el Instituto \u00a0Colombiano de Cr\u00e9dito Educativo y Estudios T\u00e9cnicos en el Exterior \u201cMariano \u00a0Ospina P\u00e9rez\u201d Icetex. \u00a0 \u00a0<\/p>\n<p>g) \u00a0Adicionado por el Decreto 342 de 2002, \u00a0art\u00edculo 1. La Visa de \u00a0Cortes\u00eda podr\u00e1 ser otorgada por el Grupo de Visas e Inmigraci\u00f3n, o por las \u00a0Oficinas Consulares de la Rep\u00fablica, al nacional ecuatoriano que pretenda \u00a0ingresar o permanecer en el territorio nacional para desarrollar alguna de las \u00a0actividades comprendidas en los Cap\u00edtulos III, IV, V, VI, y VII \u00a0del T\u00edtulo III del Decreto \u00a02107 del 8 de octubre de 2001, la cual se \u00a0regir\u00e1 por lo dispuesto en el presente decreto. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Las Misiones Diplom\u00e1ticas y Oficinas Consulares deber\u00e1n \u00a0solicitar concepto previo y autorizaci\u00f3n al Grupo Interno de Trabajo que el \u00a0Ministro de Relaciones Exteriores determine, para expedir esta visa al extranjero \u00a0que no se encuentre incluido en ninguno de los literales anteriores, o cuando \u00a0se requiera expedirla por un t\u00e9rmino superior a noventa (90) d\u00edas, sin superar \u00a0en todo caso un (1) a\u00f1o. \u00a0 \u00a0<\/p>\n<p>CAPITULO III \u00a0 \u00a0<\/p>\n<p>De la visa de negocios \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 40. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa de Negocios podr\u00e1 ser otorgada por el Grupo Interno de \u00a0Trabajo que el Ministro de Relaciones Exteriores determine o por las Oficinas \u00a0Consulares de la Rep\u00fablica, al extranjero que acredite su condici\u00f3n de \u00a0comerciante, industrial, ejecutivo y hombre de negocios que desee ingresar al \u00a0pa\u00eds con fines de negocios, o para realizar estudios de mercadeo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 41. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Modificado por el Decreto 3521 de 2003, \u00a0art\u00edculo 1\u00ba. La Visa de Negocios tendr\u00e1 una vigencia \u00a0de hasta cuatro (4) a\u00f1os para m\u00faltiples entradas y autoriza una permanencia \u00a0hasta por el t\u00e9rmino de seis (6) meses por cada ingreso. Dicha visa caducar\u00e1 si \u00a0el extranjero sobrepasa el t\u00e9rmino de permanencia autorizado.&#8221; \u00a0 \u00a0<\/p>\n<p>Texto inicial: \u201cLa Visa de Negocios tendr\u00e1 una vigencia de hasta tres (3) a\u00f1os para \u00a0m\u00faltiples entradas y autoriza una permanencia hasta por el t\u00e9rmino de seis (6) \u00a0meses por cada ingreso. Dicha visa caducar\u00e1 si el extranjero sobrepasa el \u00a0t\u00e9rmino de permanencia autorizado.\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 42. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Al amparo de esta visa el extranjero no podr\u00e1 fijar su domicilio en \u00a0el territorio nacional y las actividades que desarrolle no le podr\u00e1n generar al \u00a0titular el pago de honorarios o salarios en Colombia. \u00a0 \u00a0<\/p>\n<p>Esta visa no podr\u00e1 expedirse en calidad de beneficiario. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 43. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Inciso modificado por el Decreto 3521 de 2003, \u00a0art\u00edculo 2\u00ba. Sin perjuicio de lo dispuesto en el art\u00edculo 17, para obtener la \u00a0visa de Negocios, el extranjero, adem\u00e1s de los requisitos establecidos en el \u00a0art\u00edculo 22 del presente Decreto, deber\u00e1 presentar, seg\u00fan el caso: \u00a0 \u00a0<\/p>\n<p>Carta del representante legal de la empresa que acredite al \u00a0extranjero, precisando la actividad a desarrollar, acompa\u00f1ada de la \u00a0certificaci\u00f3n de constituci\u00f3n o representaci\u00f3n legal o documento similar, seg\u00fan \u00a0el pa\u00eds de origen. O, \u00a0 \u00a0<\/p>\n<p>Carta de la persona natural en la que se manifiesten las razones de \u00a0su solicitud de visa, respaldada por las certificaciones bancarias o de \u00a0solvencia econ\u00f3mica necesaria para realizar negocios en el pa\u00eds o, \u00a0 \u00a0<\/p>\n<p>Carta de la entidad de car\u00e1cter p\u00fablico o privado, establecida en \u00a0el territorio nacional que promueva la visita del extranjero y en la que \u00a0manifieste que se hace responsable de \u00e9ste durante su permanencia en el pa\u00eds, \u00a0acompa\u00f1ada de la certificaci\u00f3n de su existencia y representaci\u00f3n legal, seg\u00fan \u00a0el caso. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. El Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine o las Oficinas Consulares, podr\u00e1n exigir, si lo \u00a0consideran pertinente, documentos adicionales que permitan determinar la \u00a0capacidad econ\u00f3mica de la persona jur\u00eddica o natural y la conveniencia del \u00a0otorgamiento de la visa de Negocios. \u00a0 \u00a0<\/p>\n<p>CAPITULO IV \u00a0 \u00a0<\/p>\n<p>De la visa de inmigrante \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 44. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa de Inmigrante podr\u00e1 ser otorgada por el Grupo Interno de \u00a0Trabajo que el Ministro de Relaciones Exteriores determine o las Oficinas \u00a0Consulares de la Rep\u00fablica, al extranjero que pretenda ingresar al pa\u00eds, o que \u00a0se encuentre en \u00e9l, y re\u00fana las condiciones establecidas por los programas de \u00a0inmigraci\u00f3n previstos por el Gobierno Nacional, los cuales ser\u00e1n debidamente \u00a0informados por el Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine. \u00a0 \u00a0<\/p>\n<p>Se podr\u00e1 otorgar igualmente dicha visa al extranjero que venga al \u00a0pa\u00eds bajo los auspicios de la Organizaci\u00f3n Internacional para las Migraciones \u00a0(OIM) y sea solicitada expresamente por ella. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 45. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El solicitante de Visa Inmigrante, adem\u00e1s de los requisitos \u00a0establecidos en el art\u00edculo 22 del presente decreto, deber\u00e1 presentar la \u00a0documentaci\u00f3n que avale la actividad que desarrollar\u00e1 en el pa\u00eds, acreditando \u00a0su capacidad, experiencia o aptitud profesional o laboral que a juicio del \u00a0Grupo Interno de Trabajo que el Ministro de Relaciones Exteriores determine, \u00a0garantice que el solicitante y su familia, si es del caso, podr\u00e1n vivir en el \u00a0pa\u00eds. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 46. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La visa de Inmigrante tendr\u00e1 una vigencia de hasta tres (3) a\u00f1os, \u00a0para m\u00faltiples entradas. \u00a0 \u00a0<\/p>\n<p>CAPITULO V \u00a0 \u00a0<\/p>\n<p>De la visa de tripulante \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 47. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Sin perjuicio de lo dispuesto en los Tratados Internacionales de los \u00a0cuales Colombia haga parte, la Visa de Tripulante podr\u00e1 ser expedida por el \u00a0Grupo Interno de Trabajo que el Ministro de Relaciones Exteriores determine o \u00a0las Oficinas Consulares de la Rep\u00fablica, al extranjero tripulante o miembro de \u00a0un medio de transporte internacional o de una embarcaci\u00f3n pesquera que ingrese \u00a0al territorio nacional, de acuerdo con lo establecido en el art\u00edculo 101 de la \u00a0Constituci\u00f3n Pol\u00edtica de Colombia. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 48. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El solicitante de Visa de Tripulante, adem\u00e1s de los requisitos \u00a0establecidos en el art\u00edculo 22 del presente decreto, deber\u00e1 presentar: \u00a0 \u00a0<\/p>\n<p>a) Carta del representante legal de la empresa responsable del \u00a0medio de transporte internacional o de la embarcaci\u00f3n pesquera, seg\u00fan el caso, \u00a0indicando la actividad a desarrollar y que se obliga ante el Gobierno Nacional \u00a0a responder por la permanencia del extranjero en el territorio nacional y su \u00a0salida del pa\u00eds; \u00a0 \u00a0<\/p>\n<p>b) Certificado de existencia y representaci\u00f3n legal de la empresa; \u00a0 \u00a0<\/p>\n<p>c) Nota de la empresa responsable de la embarcaci\u00f3n pesquera, seg\u00fan \u00a0el caso, en la cual manifieste que cumple con las normas establecidas para la \u00a0contrataci\u00f3n de tripulantes extranjeros. En este caso debe aportar constancia \u00a0de haber informado sobre el particular a la autoridad mar\u00edtima. \u00a0 \u00a0<\/p>\n<p>El tripulante de embarcaci\u00f3n de bandera extranjera, que realice \u00a0actividades de pesca en aguas jurisdiccionales colombianas, deber\u00e1 aportar, \u00a0adem\u00e1s, los documentos que acrediten que la nave tiene los respectivos permisos \u00a0de pesca vigentes. \u00a0 \u00a0<\/p>\n<p>El tripulante de embarcaci\u00f3n de bandera colombiana, administrada \u00a0por armador nacional o extranjero, deber\u00e1 adjuntar adem\u00e1s, nota del armador o \u00a0de la empresa responsable en la cual se indique los t\u00e9rminos del contrato de \u00a0enrolamiento, especificando el cargo e idoneidad del tripulante. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. La Visa de Tripulante caducar\u00e1 por el incumplimiento de \u00a0las normas vigentes sobre proporcionalidad entre tripulantes nacionales y \u00a0extranjeros, informando al Ministerio de Relaciones Exteriores por la autoridad \u00a0competente. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 49. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La estad\u00eda del tripulante se \u00a0autorizar\u00e1 por el tiempo de permanencia del medio de transporte en el \u00a0territorio nacional. \u00a0 \u00a0<\/p>\n<p>En el caso de la actividad pesquer a, la \u00a0estad\u00eda del tripulante extranjero se autorizar\u00e1 seg\u00fan lo indique el permiso de \u00a0pesca, o el contrato de enrolamiento. En todo caso la vigencia de esta visa no \u00a0podr\u00e1 ser superior a un (1) a\u00f1o, y permitir\u00e1 a su titular m\u00faltiples entradas. \u00a0 \u00a0<\/p>\n<p>CAPITULO VI \u00a0 \u00a0<\/p>\n<p>De la visa temporal \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 50. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal podr\u00e1 ser otorgada por el Grupo Interno de Trabajo \u00a0que el Ministro de Relaciones Exteriores determine o las Oficinas Consulares de \u00a0la Rep\u00fablica, para m\u00faltiples entradas, al extranjero que pretenda desarrollar \u00a0alguna de las actividades comprendidas en el presente cap\u00edtulo. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. La Visa Temporal caducar\u00e1 si el extranjero se ausenta \u00a0del territorio nacional por un t\u00e9rmino superior a ciento ochenta (180) d\u00edas \u00a0continuos. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 51. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal solo podr\u00e1 ser solicitada por primera vez ante una \u00a0Oficina Consular de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>Se entiende que una Visa Temporal se solicita por primera vez \u00a0cuando: \u00a0 \u00a0<\/p>\n<p>a) El solicitante haya sido titular de Visa Temporal y no present\u00f3 \u00a0nueva solicitud dentro de los treinta (30) d\u00edas anteriores al vencimiento de la \u00a0visa de que era titular, salvo caso fortuito o fuerza mayor debidamente \u00a0comprobados; \u00a0 \u00a0<\/p>\n<p>b) El solicitante no ha sido titular de Visa para ingresar al \u00a0territorio nacional; \u00a0 \u00a0<\/p>\n<p>c) El solicitante haya sido titular de Visa de Turismo o Visa \u00a0Visitante, salvo para prestar servicios t\u00e9cnicos. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Se except\u00faan de lo establecido en el presente art\u00edculo \u00a0la Visa Temporal en las categor\u00edas Padre o Madre de Nacional Colombiano, \u00a0Estudiante, Empresarial y Refugiado o Asilado, las cuales podr\u00e1n ser expedidas \u00a0por primera vez en Colombia. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0PRIMERA \u00a0 \u00a0<\/p>\n<p>De la Visa Temporal \u00a0Trabajador \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 52. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Trabajador podr\u00e1 ser expedida por el Grupo Interno \u00a0de Trabajo que el Ministro de Relaciones Exteriores determine o las Oficinas \u00a0Consulares de la Rep\u00fablica, en los siguientes casos: \u00a0 \u00a0<\/p>\n<p>a) Al extranjero contratado por empresa, entidad o instituci\u00f3n \u00a0p\u00fablica o privada, o persona natural que pretenda ingresar, o permanecer en el pa\u00eds, \u00a0para efectuar un trabajo o actividad en su especialidad; \u00a0 \u00a0<\/p>\n<p>b) Al extranjero que pretenda ingresar o permanecer en el pa\u00eds, en \u00a0virtud de acuerdos acad\u00e9micos celebrados entre instituciones de educaci\u00f3n \u00a0superior, o acuerdos interadministrativos, en \u00e1reas \u00a0especializadas. D icho extranjero deber\u00e1 comprobar su idoneidad, mediante la \u00a0presentaci\u00f3n del t\u00edtulo debidamente homologado o certificaciones de trabajo \u00a0cuando no sea profesional; \u00a0 \u00a0<\/p>\n<p>c) Al extranjero que ingres\u00f3 con Visa Visitante o Permiso de \u00a0Ingreso para prestar servicios t\u00e9cnicos urgentes, cuando la entidad que \u00a0solicit\u00f3 el servicio considere indispensable la permanencia del extranjero por \u00a0un tiempo superior al inicialmente otorgado, de acuerdo con lo establecido en \u00a0el par\u00e1grafo de los art\u00edculos 76 y 96 del presente decreto; \u00a0 \u00a0<\/p>\n<p>d) Al periodista extranjero contratado por agencia de noticias o de \u00a0informaci\u00f3n nacional o internacional, o al que tenga calidad de corresponsal, \u00a0lo cual deber\u00e1 acreditarse; \u00a0 \u00a0<\/p>\n<p>e) Al extranjero integrante de un grupo art\u00edstico, deportivo o \u00a0cultural contratado en raz\u00f3n de su actividad, cuando \u00e9sta sea remunerada; \u00a0 \u00a0<\/p>\n<p>f) Al extranjero nombrado por un \u00f3rgano o entidad del Estado; \u00a0 \u00a0<\/p>\n<p>g) A los directivos, t\u00e9cnicos y personal administrativo de entidad \u00a0p\u00fablica o privada extranjera, de car\u00e1cter comercial o industrial, trasladados \u00a0desde el exterior, para cubrir cargos espec\u00edficos en sus empresas; \u00a0 \u00a0<\/p>\n<p>h) A los voluntarios y misioneros que no hagan parte de la \u00a0jerarqu\u00eda de una iglesia, confesi\u00f3n, denominaci\u00f3n religiosa, federaci\u00f3n, \u00a0confederaci\u00f3n o asociaci\u00f3n de ministros religiosos. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 53. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Esta visa se expedir\u00e1 a solicitud y bajo la responsabilidad de la \u00a0empresa, entidad, instituci\u00f3n o persona natural que avale la petici\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 54. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Esta visa podr\u00e1 otorgarse hasta por el t\u00e9rmino de dos (2) a\u00f1os, \u00a0para m\u00faltiples entradas. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Cuando se trate de un grupo art\u00edstico, deportivo o cultural, \u00a0que pretenda ingresar al pa\u00eds con el prop\u00f3sito de brindar espect\u00e1culo p\u00fablico, \u00a0se expedir\u00e1 la Visa Temporal Trabajador hasta por seis (6) meses, previa \u00a0presentaci\u00f3n, en un ejemplar, de los documentos indicados en los numerales 1, 2 \u00a0y 3 del art\u00edculo 55 del presente decreto, anexando un listado de los \u00a0integrantes de \u00e9ste, indicando los n\u00fameros de sus pasaportes y la nacionalidad \u00a0de los mismos, sin perjuicio del diligenciamiento individual y firma de la \u00a0solicitud de visa por parte del extranjero y fotocopia de los pasajes de salida \u00a0del pa\u00eds. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 55. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Sin perjuicio de lo establecido en el art\u00edculo 17, el solicitante \u00a0de esta visa, adem\u00e1s de los requisitos establecidos en el art\u00edculo 22 del \u00a0presente decreto, deber\u00e1 presentar: \u00a0 \u00a0<\/p>\n<p>1. Original del contrato, o acto administrativo, o acuerdo de \u00a0vinculaci\u00f3n, seg\u00fan el caso, cuando el extranjero sea contratado por empresa, \u00a0entidad o instituci\u00f3n privada o p\u00fablica. En el caso del extranjero que sea \u00a0trasladado de la casa matriz a la filial en Colombia, deber\u00e1 presentar nota de \u00a0la entidad comercial o industrial en que especifique el cargo que viene a \u00a0ocupar. \u00a0 \u00a0<\/p>\n<p>2. Nota original de la empresa, entidad o instituci\u00f3n p\u00fablica o \u00a0privada contratante mediante la cual se compromete ante el Gobierno Nacional a \u00a0sufragar todos l os gastos de regreso al pa\u00eds de origen o al \u00faltimo lugar de residencia \u00a0del extranjero contratado, as\u00ed como de su familia, si es del caso, al t\u00e9rmino \u00a0del contrato, o cuando proceda la cancelaci\u00f3n de la visa, la deportaci\u00f3n o la \u00a0expulsi\u00f3n, seg\u00fan lo dispuesto en el presente decreto. \u00a0 \u00a0<\/p>\n<p>3 Certificado de existencia y representaci\u00f3n legal o personer\u00eda \u00a0jur\u00eddica, seg\u00fan el caso, cuando el contratante sea persona jur\u00eddica, expedido \u00a0con una antelaci\u00f3n no mayor de tres (3) meses. Cuando se considere necesario se \u00a0solicitar\u00e1n los balances de la empresa que demuestren su solvencia econ\u00f3mica, \u00a0as\u00ed como tambi\u00e9n se podr\u00e1 solicitar fotocopia de la declaraci\u00f3n de renta. Lo \u00a0dispuesto en este numeral no se exigir\u00e1 a los \u00f3rganos, entidades o \u00a0instituciones del Estado colombiano. \u00a0 \u00a0<\/p>\n<p>Cuando el contratante sea persona natural deber\u00e1 demostrar su solvencia \u00a0econ\u00f3mica, con ingresos mensuales superiores a treinta (30) salarios m\u00ednimos \u00a0legales vigentes. \u00a0 \u00a0<\/p>\n<p>4. Certificaci\u00f3n del Ministerio de Trabajo y Seguridad Social, \u00a0donde conste que con la incorporaci\u00f3n del extranjero se respeta la \u00a0proporcionalidad entre trabajadores nacionales y extranjeros, de acuerdo con lo \u00a0establecido en el C\u00f3digo Sustantivo del Trabajo, salvo cuando se trate de \u00a0grupos culturales, espect\u00e1culo p\u00fablico, deportivo o art\u00edstico. As\u00ed mismo se \u00a0exonera de este requisito cuando la entidad contratante sea un \u00f3rgano, entidad \u00a0o instituci\u00f3n del Estado. \u00a0 \u00a0<\/p>\n<p>5. Fotocopia aut\u00e9ntica del t\u00edtulo profesional, debidamente \u00a0homologado o convalidado ante el Icfes, matr\u00edcula o \u00a0tarjeta profesional o constancia de la experiencia, seg\u00fan el caso, o permiso \u00a0provisional o licencia para ejercer en Colombia la profesi\u00f3n o actividad \u00a0respectiva, otorgada por la entidad competente. \u00a0 \u00a0<\/p>\n<p>Para ejercer la profesi\u00f3n o actividad autorizada en la visa, el \u00a0extranjero deber\u00e1 cumplir con los mismos requisitos exigidos para los \u00a0nacionales colombianos, consagrados en las normas vigentes y aportar\u00e1 los \u00a0documentos que le permitan el ejercicio de la profesi\u00f3n respectiva. \u00a0 \u00a0<\/p>\n<p>Para aquellas profesiones u oficios no regulados, que el extranjero \u00a0pretenda desarrollar en Colombia, deber\u00e1 acreditar experiencia o idoneidad \u00a0mediante la presentaci\u00f3n de constancias de trabajo. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0SEGUNDA \u00a0 \u00a0<\/p>\n<p>De la Visa Temporal \u00a0C\u00f3nyuge o Compa\u00f1ero(a) Permanente\u00a0<\/p>\n<p>\u00a0 de Nacional Colombiano \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 56. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal C\u00f3nyuge o Compa\u00f1ero(a) Permanente de Nacional \u00a0Colombiano podr\u00e1 ser otorgada por el Grupo Interno de Trabajo que el Ministro \u00a0de Relaciones Exteriores determine o las Oficinas Consulares de la Rep\u00fablica, \u00a0hasta por el t\u00e9rmino de dos (2) a\u00f1os, para m\u00faltiples entradas, al extranjero \u00a0que haya contra\u00eddo matrimonio v\u00e1lido con un nacional colombiano, o al que re\u00fana \u00a0los requisitos para ser considerado como compa\u00f1ero permanente, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 57. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Sin perjuicio de lo establecido en el art\u00edculo 17, el solicitante \u00a0de esta v isa, adem\u00e1s de los requisitos establecidos en el art\u00edculo 22 del \u00a0presente decreto, deber\u00e1 presentar: \u00a0 \u00a0<\/p>\n<p>1. Registro civil de matrimonio colombiano, expedido con antelaci\u00f3n \u00a0no mayor a noventa (90) d\u00edas; o copia de la providencia judicial mediante la \u00a0cual se acredite la existencia de la uni\u00f3n singular y permanente de hecho, \u00a0seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>2. Fotocopia de la c\u00e9dula de ciudadan\u00eda del c\u00f3nyuge o compa\u00f1ero(a) \u00a0colombiano. \u00a0 \u00a0<\/p>\n<p>3. Nota escrita del nacional colombiano solicitando se le expida la \u00a0visa al extranjero. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. En el evento en que el extranjero desee ejercer una \u00a0actividad diferente de hogar o estudiante, deber\u00e1 aportar los documentos que \u00a0demuestren la actividad a desarrollar en Colombia, en concordancia con las \u00a0exigencias establecidas para los nacionales colombianos, y certificado de \u00a0proporcionalidad entre trabajadores nacionales y extranjeros cuando sea \u00a0contratado por entidad privada. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. Cuando el oficio de solicitud de la visa y la c\u00e9dula \u00a0de ciudadan\u00eda no sean presentados en forma personal por el nacional colombiano, \u00a0deber\u00e1n estar debidamente autenticados ante el C\u00f3nsul o Notario colombiano, \u00a0seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 3\u00b0. Cuando la solicitud de visa se presente en el \u00a0exterior, se aceptar\u00e1 en el caso de compa\u00f1ero(a) permanente, el documento que \u00a0compruebe la convivencia o uni\u00f3n marital en dicho pa\u00eds. En todo caso para la \u00a0solicitud de nueva visa ante el Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine, se deber\u00e1 presentar la respectiva providencia \u00a0judicial. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0TERCERA \u00a0 \u00a0<\/p>\n<p>De la Visa Temporal \u00a0Padre o Madre de Nacional Colombiano \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 58. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Padre o Madre de Nacional Colombiano, podr\u00e1 ser \u00a0expedida por el Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine o las Oficinas Consulares de la Rep\u00fablica, al extranjero \u00a0que sea padre o madre de nacional colombiano, de acuerdo con lo establecido en \u00a0el art\u00edculo 96 de la Constituci\u00f3n Pol\u00edtica de Colombia. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 59. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Sin perjuicio de lo establecido en el art\u00edculo 17, el solicitante \u00a0de esta visa, adem\u00e1s de los requisitos establecidos en el art\u00edculo 22 del \u00a0presente decreto, deber\u00e1 presentar: \u00a0 \u00a0<\/p>\n<p>1. Registro civil de nacimiento del hijo colombiano con una fecha \u00a0de expedici\u00f3n no superior a noventa (90) d\u00edas. \u00a0 \u00a0<\/p>\n<p>2. Nota escrita del padre o madre colombiano, manifestando que el \u00a0extranjero responde econ\u00f3micamente por el hijo o nota del hijo cuando \u00e9ste sea \u00a0mayor de edad. En caso de fallecimiento del padre o madre colombiano bastar\u00e1 \u00a0que el extranjero aporte la respectiva acta de defunci\u00f3n o nota del extranjero \u00a0titular de Visa de Residente, padre del menor nacido en Colombia, en el caso de \u00a0que ambos padres sean extranjeros. \u00a0 \u00a0<\/p>\n<p>3. Fotocopia de la c\u00e9dula de ciudadan\u00eda del padr \u00a0e o madre o hijo colombiano, o de la c\u00e9dula de extranjer\u00eda, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. En el evento en que el extranjero desee ejercer una \u00a0actividad diferente de hogar o estudiante, deber\u00e1 aportar los documentos que \u00a0demuestren la actividad a desarrollar en Colombia, en concordancia con las \u00a0exigencias establecidas para los nacionales colombianos, y certificado de \u00a0proporcionalidad entre trabajadores nacionales y extranjeros, cuando sea \u00a0contratado por entidad privada. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. Cuando la nota de solicitud de la visa y la c\u00e9dula de \u00a0ciudadan\u00eda o de extranjer\u00eda no sean presentadas en forma personal por el \u00a0nacional colombiano, o el extranjero residente, deber\u00e1n estar debidamente \u00a0autenticadas ante el C\u00f3nsul o Notario colombiano, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 60. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Padre o Madre de Nacional Colombiano podr\u00e1 ser \u00a0expedida por un t\u00e9rmino m\u00e1ximo de hasta tres (3) a\u00f1os, para m\u00faltiples entradas. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0CUARTA \u00a0 \u00a0<\/p>\n<p>De la Visa Temporal \u00a0Religioso \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 61. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Religioso podr\u00e1 ser otorgada por el Grupo Interno \u00a0de Trabajo que el Ministro de Relaciones Exteriores determine o las Oficinas \u00a0Consulares, al extranjero que forme parte de la jerarqu\u00eda de una iglesia, \u00a0confesi\u00f3n, denominaci\u00f3n religiosa, federaci\u00f3n, confederaci\u00f3n o asociaci\u00f3n de \u00a0ministros religiosos, debidamente reconocida por la autoridad competente, o \u00a0certificada mediante constancia de la Arquidi\u00f3cesis, seg\u00fan el caso, que venga a \u00a0desarrollar en forma exclusiva actividades propias de su culto, bajo la \u00a0responsabilidad de la entidad religiosa. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 62. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Religioso podr\u00e1 ser expedida hasta por un t\u00e9rmino \u00a0m\u00e1ximo de dos (2) a\u00f1os, para m\u00faltiples entradas. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 63. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Sin perjuicio de lo establecido en el art\u00edculo 17, el solicitante \u00a0de esta visa, adem\u00e1s de los requisitos establecidos en el art\u00edculo 22 del \u00a0presente decreto, deber\u00e1 presentar: \u00a0 \u00a0<\/p>\n<p>1. Certificaci\u00f3n expedida por el Ministerio del Interior o de la \u00a0Arquidi\u00f3cesis, seg\u00fan el caso, en la que conste que la iglesia, confesi\u00f3n o \u00a0denominaci\u00f3n religiosa o sus federaciones, confederaciones y asociaciones de \u00a0ministros, se encuentran debidamente inscritas o registradas. \u00a0 \u00a0<\/p>\n<p>2. Certificaci\u00f3n expedida por el representante legal o superior de \u00a0la Comunidad, en la cual se especifique la misi\u00f3n que viene a cumplir el \u00a0extranjero y se indique el v\u00ednculo de \u00e9ste con la entidad religiosa. \u00a0 \u00a0<\/p>\n<p>3. Nota del representante legal o superior jer\u00e1rquico de la \u00a0entidad, religiosa, mediante la cual se compromete ante el Gobierno Nacional a \u00a0sufragar todos los gastos de permanencia y regreso al pa\u00eds de origen o al \u00a0\u00faltimo lugar de residencia del extranjero, as\u00ed como de su familia, cuando deje \u00a0de pertenecer a la comunidad religiosa, o cuando por cualquier motivo proceda \u00a0la cancelaci\u00f3n de la visa, deportaci\u00f3n o expulsi\u00f3n, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>4. Documentos que demuestren la solvencia econ\u00f3mica de la iglesia, \u00a0confesi\u00f3n, denominaci\u00f3n religiosa, federaci\u00f3n, confederaci\u00f3n o asociaci\u00f3n de \u00a0ministros religiosos o del extranjero. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 64. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Al extranjero que no haga parte de la jerarqu\u00eda de una iglesia, \u00a0confesi\u00f3n, denominaci\u00f3n religiosa, federaci\u00f3n, confederaci\u00f3n o asociaci\u00f3n de \u00a0ministros religiosos, seg\u00fan el caso, se le conceder\u00e1 la visa de que trata el \u00a0art\u00edculo 52 del presente decreto o la que corresponda y deber\u00e1 cumplir los \u00a0requisitos establecidos. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0QUINTA \u00a0 \u00a0<\/p>\n<p>De la Visa Temporal \u00a0Estudiante \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 65. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Estudiante podr\u00e1 ser otorgada por el Grupo Interno \u00a0de Trabajo que el Ministro de Relaciones Exteriores determine o las Oficinas \u00a0Consulares de la Rep\u00fablica, al extranjero que pretenda cursar estudios como \u00a0alumno regular o en virtud de programas de intercambio estudiantil, en \u00a0establecimientos educativos p\u00fablicos o privados, reconocidos por el Gobierno \u00a0Nacional. \u00a0 \u00a0<\/p>\n<p>Cuando dentro del programa de estudios se establezca pr\u00e1ctica \u00a0laboral como requisito acad\u00e9mico, se podr\u00e1 autorizar como ocupaci\u00f3n la de \u00a0practicante, previa certificaci\u00f3n de la entidad educativa. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. La Visa Temporal Estudiante podr\u00e1 cambiarse en el \u00a0pa\u00eds por otra visa al t\u00e9rmino de sus estudios. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. La Visa Temporal Estudiante no autoriza a su titular \u00a0a ejercer actividad diferente, salvo cuando se trate de pr\u00e1ctica como requisito \u00a0acad\u00e9mico y en concordancia con lo dispuesto en el par\u00e1grafo 3\u00b0 del art\u00edculo \u00a0153 del presente decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 66. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El solicitante de esta visa, adem\u00e1s de los requisitos establecidos \u00a0en el art\u00edculo 22 del presente decreto, deber\u00e1 presentar: \u00a0 \u00a0<\/p>\n<p>1. Fotocopia del certificado de admisi\u00f3n o de matr\u00edcula expedido \u00a0por el establecimiento educativo correspondiente o fotocopia aut\u00e9ntica del \u00a0convenio celebrado entre la entidad patrocinante y el establecimiento educativo \u00a0por el cual \u00e9ste se compromete a aceptar al estudiante amparado por el convenio \u00a0interinstitucional, cuando se trate de estudiante de intercambio. \u00a0 \u00a0<\/p>\n<p>2. Fotocopia de la resoluci\u00f3n de reconocimiento de personer\u00eda \u00a0jur\u00eddica del establecimiento educativo, expedido por la autoridad \u00a0correspondiente. \u00a0 \u00a0<\/p>\n<p>3. Documento que demuestre la solvencia econ\u00f3mica del titular o de \u00a0sus padres o representante legal, o de la persona que garantice los gastos de \u00a0su permanencia en el pa\u00eds. \u00a0 \u00a0<\/p>\n<p>4. Certificaci\u00f3n o constancia del Organismo Internacional, \u00a0instituci\u00f3n estatal o entidad privada que otorga la beca, en el caso del \u00a0estudiante becado. Igualmente el certificado de solvencia econ\u00f3mica del titular \u00a0o de los padres en el caso de que la subvenci\u00f3n sea parcial. \u00a0 \u00a0<\/p>\n<p>5. Autorizaci\u00f3n de los padres para su permanencia en el pa\u00eds, \u00a0cuando se trate de menores de edad y designaci\u00f3n del responsable del menor \u00a0durante su permanencia en el territorio nacional. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 67. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La vigencia de esta visa podr\u00e1 ser expedida hasta por el t\u00e9rmino de \u00a0un (1) a\u00f1o y podr\u00e1 ser expedida nueva visa por periodos iguales hasta la \u00a0finalizaci\u00f3n de los estudios y la obtenci\u00f3n del t\u00edtulo respectivo. \u00a0 \u00a0<\/p>\n<p>SECCION SEXTA \u00a0 \u00a0<\/p>\n<p>De la Visa Temporal \u00a0Empresarial \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 68. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Empresarial \u00a0podr\u00e1 ser otorgada por el Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine o las Oficinas Consulares de la Rep\u00fablica, al \u00a0extranjero, que sea representante legal, directivo o ejecutivo de empresa \u00a0extranjera, comercial, industrial o de servicio, que tenga v\u00ednculo econ\u00f3mico con \u00a0compa\u00f1\u00eda nacional o extranjera en Colombia. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 69. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Empresarial podr\u00e1 expedirse por un t\u00e9rmino de \u00a0hasta cinco a\u00f1os (5) a\u00f1os, para m\u00faltiples entradas, y autoriza una permanencia \u00a0de hasta un (1) a\u00f1o por cada ingreso. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 70. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero titular de Visa Temporal Empresarial podr\u00e1 al amparo \u00a0de la misma desarrollar las actividades propias de la gesti\u00f3n empresarial relacionada \u00a0con los intereses que representa, tales como asistir a juntas de socios, \u00a0celebrar negocios, supervisar el manejo de las empresas, entre otras, con las \u00a0cuales existe el v\u00ednculo jur\u00eddico, estrat\u00e9gico y econ\u00f3mico. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 71. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para obtener la Visa Temporal Empresarial, el interesado adem\u00e1s de \u00a0los requisitos establecidos en el art\u00edculo 22 del presente decreto, deber\u00e1 \u00a0presentar seg\u00fan el caso: \u00a0 \u00a0<\/p>\n<p>Carta del representante legal de la persona jur\u00eddica extranjera que \u00a0acredite al solicitante debidamente autenticada por Consulado de Colombia, \u00a0indicando el cargo que ocupa dentro de la organizaci\u00f3n y la actividad que va a \u00a0desarrollar en Colombia, acompa\u00f1ada de la certificaci\u00f3n de constituci\u00f3n o \u00a0representaci\u00f3n legal de la empresa o documento similar, seg\u00fan el pa\u00eds de \u00a0origen; o, \u00a0 \u00a0<\/p>\n<p>Carta en el mismo sentido y con los mismos anexos, suscrita por el \u00a0representante legal de la instituci\u00f3n de car\u00e1cter p\u00fablico o privado establecida \u00a0en el territorio nacional que promueva la visita del extranjero al pa\u00eds y \u00a0documento que demuestre ese v\u00ednculo econ\u00f3mico entre las instituciones. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 72. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El titular de Visa Temporal \u00a0Empresarial no estar\u00e1 sometido a registro en el DAS. Si lo desea, podr\u00e1 \u00a0solicitar la expedici\u00f3n de c\u00e9dula de extranjer\u00eda. \u00a0 \u00a0<\/p>\n<p>SECCION SEPTIMA \u00a0 \u00a0<\/p>\n<p>De la Visa Temporal \u00a0Especial \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 73. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Especial podr\u00e1 ser otorgada por el Grupo Interno \u00a0de Trabajo que el Ministro de Relaciones Exteriores determine o por las \u00a0Oficinas Consulares de la Rep\u00fablica, al extranjero que pretenda ingresar al te rritorio nacional en cualquiera de los siguientes casos: \u00a0 \u00a0<\/p>\n<p>a) Para tratamiento m\u00e9dico cuando \u00e9ste no sea posible realizarlo \u00a0dentro de los t\u00e9rminos de los art\u00edculos 78 y 96 del presente decreto para la \u00a0Visa de Visitante o el Permiso de Ingreso; \u00a0 \u00a0<\/p>\n<p>b) Para intervenir en procesos administrativos o judiciales; \u00a0 \u00a0<\/p>\n<p>c) Como socio o propietario de establecimiento de comercio o de \u00a0sociedad comercial, con domicilio en Colombia; \u00a0 \u00a0<\/p>\n<p>d) Como pensionado; \u00a0 \u00a0<\/p>\n<p>e) Como rentista; \u00a0 \u00a0<\/p>\n<p>f) Como cooperante o voluntario de entidad sin \u00e1nimo de lucro u \u00a0Organizaci\u00f3n No Gubernamental, ONG, o a quien debidamente presentado por un \u00a0Organismo Internacional o una Misi\u00f3n Diplom\u00e1tica, se\u00f1ale que viene al pa\u00eds a \u00a0desarrollar labores de beneficio social, asistencia, verificaci\u00f3n, observaci\u00f3n \u00a0o ayuda humanitaria; \u00a0 \u00a0<\/p>\n<p>g) Para contraer matrimonio; \u00a0 \u00a0<\/p>\n<p>h) Para tr\u00e1mites de adopci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. En los casos del literal f), las Oficinas Consulares \u00a0de la Rep\u00fablica deber\u00e1n obtener autorizaci\u00f3n previa del Grupo Interno de \u00a0Trabajo que el Ministro de Relaciones Exteriores determine, para otorgar la \u00a0visa. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. Cuando el extranjero pretenda ingresar o permanecer \u00a0en el pa\u00eds para llevar a cabo ocupaciones o actividades no contempladas en el \u00a0presente art\u00edculo o para desarrollar actividades de inter\u00e9s para el pa\u00eds, se \u00a0podr\u00e1 conceder esta visa. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 74. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Sin perjuicio de lo establecido en el art\u00edculo 17, el solicitante \u00a0de esta visa deber\u00e1 presentar, adem\u00e1s de los requisitos establecidos en el \u00a0art\u00edculo 22 del presente decreto, los documentos que acrediten la actividad a desarrollar, \u00a0seg\u00fan el caso: \u00a0 \u00a0<\/p>\n<p>1. El solicitante de la Visa Temporal Especial, para tratamiento \u00a0m\u00e9dico, deber\u00e1 presentar: \u00a0 \u00a0<\/p>\n<p>a) Certificaci\u00f3n expedida por el facultativo en que indique la \u00a0necesidad del tratamiento y el t\u00e9rmino requerido para el mismo, refrendada por \u00a0la instituci\u00f3n m\u00e9dica correspondiente; \u00a0 \u00a0<\/p>\n<p>b) Documento que acredite la solvencia econ\u00f3mica para permanecer en \u00a0Colombia durante el tiempo que demande el tratamiento; \u00a0 \u00a0<\/p>\n<p>c) Fotocopia del pasaje de salida del pa\u00eds; \u00a0 \u00a0<\/p>\n<p>d) Fotocopia de la visa o del permiso de ingreso al pa\u00eds concedido \u00a0por el DAS, cuando la solicitud sea presentada ante el Grupo Interno de Trabajo \u00a0que el Ministro de Relaciones Exteriores determine. \u00a0 \u00a0<\/p>\n<p>2. El solicitante de Visa Temporal Especial para interven ir en procesos administrativos o judiciales deber\u00e1 \u00a0aportar: \u00a0 \u00a0<\/p>\n<p>a) Certificaci\u00f3n expedida por autoridad competente donde se \u00a0indique, entre otros aspectos, la clase del proceso o tr\u00e1mite, el estado \u00a0procesal del mismo, y si el extranjero est\u00e1 vinculado, es parte, tercero interesado, \u00a0o tercero incidental; \u00a0 \u00a0<\/p>\n<p>b) Fotocopia del pasaje de salida del pa\u00eds. \u00a0 \u00a0<\/p>\n<p>3. El solicitante de Visa Temporal Especial, como socio o \u00a0propietario de establecimiento de comercio o de sociedad comercial, deber\u00e1 \u00a0presentar: \u00a0 \u00a0<\/p>\n<p>a) Certificado existencia y representaci\u00f3n legal expedido por la \u00a0C\u00e1mara de Comercio, con una antelaci\u00f3n no superior a noventa (90) d\u00edas, en el \u00a0que conste que el extranjero es socio o propietario del establecimiento \u00a0registrado, indicando un capital o activo registrado de propiedad del extranjero \u00a0solicitante, no menor a cien (100) salarios m\u00ednimos legales mensuales vigentes. \u00a0 \u00a0<\/p>\n<p>Si se trata de una sociedad an\u00f3nima deber\u00e1 adjuntarse un \u00a0certificado de la composici\u00f3n accionar\u00eda suscrita por el revisor fiscal, \u00a0indicando el valor de las acciones de propiedad del extranjero solicitante, el \u00a0cual no podr\u00e1 ser inferior a cien (100) salarios m\u00ednimos legales mensuales \u00a0vigentes; \u00a0 \u00a0<\/p>\n<p>b) Balances de la empresa o del establecimiento de comercio \u00a0debidamente firmados por contador p\u00fablico, adjuntando fotocopia aut\u00e9ntica de su \u00a0tarjeta profesional, y cuando sea necesario por el revisor fiscal y fotocopia \u00a0de la declaraci\u00f3n de renta de la empresa correspondiente al \u00faltimo a\u00f1o \u00a0gravable. Para la autorizaci\u00f3n de esta visa, el Ministerio de Relaciones \u00a0Exteriores tendr\u00e1 en cuenta la actividad que desarrolla la empresa o al \u00a0establecimiento de comercio, su inter\u00e9s social y su capacidad econ\u00f3mica. \u00a0 \u00a0<\/p>\n<p>4. Se conceder\u00e1 Visa Temporal Especial con ocupaci\u00f3n pensionado, al \u00a0extranjero que compruebe recibir pensi\u00f3n en una suma mensual equivalente a diez \u00a0(10) salarios m\u00ednimos legales vigentes, provenientes de fuentes externas, o de \u00a0Gobierno, organismo, o empresa particular extranjera. \u00a0 \u00a0<\/p>\n<p>El solicitante de Visa Temporal Especial como pensionado deber\u00e1 \u00a0presentar certificaci\u00f3n expedida por autoridad competente, Gobierno, empresa \u00a0p\u00fablica o privada o entidad extranjera en la que conste que recibe pensi\u00f3n, la \u00a0cual deber\u00e1 ser legalizada ante C\u00f3nsul Colombiano o apostillada, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>5. Se conceder\u00e1 Visa Temporal Especial con ocupaci\u00f3n rentista al \u00a0extranjero que compruebe recibir ingresos mensuales, regulares y permanentes, \u00a0provenientes de fuentes externas, en cuant\u00eda no inferior al equivalente a \u00a0quince (15) salarios m\u00ednimos legales mensuales vigentes. \u00a0 \u00a0<\/p>\n<p>El solicitante de Visa Temporal Especial como rentista deber\u00e1 \u00a0presentar constancia expedida por entidad oficial, bancos, empresas \u00a0financieras, instituciones de seguridad social, compa\u00f1\u00edas de seguros o \u00a0cualquier otra empresa privada, reconocida por el Gobierno respectivo, que \u00a0pague o gire la renta que permita comprobar el monto de los ingresos originados \u00a0en el exterio r, la cual deber\u00e1 ser debidamente \u00a0traducida al castellano, autenticada ante el respectivo funcionario Consular de \u00a0la Rep\u00fablica y legalizada ante el Ministerio de Relaciones Exteriores, de \u00a0conformidad con lo establecido por las normas del C\u00f3digo de Procedimiento Civil \u00a0o apostillada cuando corresponda. \u00a0 \u00a0<\/p>\n<p>6. El cooperante o voluntario de entidad sin \u00e1nimo de lucro u \u00a0Organizaci\u00f3n No Gubernamental, ONG, o quien haya sido presentado por una Misi\u00f3n \u00a0Diplom\u00e1tica u Organismo Internacional, deber\u00e1 aportar: \u00a0 \u00a0<\/p>\n<p>a) Carta de la entidad sin \u00e1nimo de lucro u Organizaci\u00f3n No \u00a0Gubernamental, o de la Misi\u00f3n u Organismo Internacional, indicando la actividad \u00a0que el extranjero viene a desarrollar en el pa\u00eds, el programa de trabajo que va \u00a0a realizar en el que se especifique su duraci\u00f3n, la agenda prevista y las \u00a0instituciones y entidades p\u00fablicas o privadas con las cuales pretenda \u00a0entrevistarse; \u00a0 \u00a0<\/p>\n<p>b) Certificado de existencia y representaci\u00f3n legal de la entidad \u00a0sin \u00e1nimo de lucro u Organizaci\u00f3n No Gubernamental, expedida por la autoridad \u00a0competente colombiana, con una antelaci\u00f3n no mayor a 30 d\u00edas. Cuando la entidad \u00a0o la ONG no tenga sede en nuestro pa\u00eds, deber\u00e1 acreditar una copia certificada \u00a0de la escritura constitutiva o del instrumento que acredite su existencia, \u00a0traducida al espa\u00f1ol, en la que conste que dicha organizaci\u00f3n tiene una \u00a0antig\u00fcedad no inferior a cinco (5) a\u00f1os, contados a partir de la fecha de su \u00a0constituci\u00f3n, o cuente con status consultivo del Consejo Social de la \u00a0Organizaci\u00f3n de las Naciones Unidas; \u00a0 \u00a0<\/p>\n<p>c) Documentos con los cuales se demuestre la solvencia econ\u00f3mica \u00a0del extranjero; \u00a0 \u00a0<\/p>\n<p>d) Documentos con los cuales se compruebe que el extranjero es \u00a0miembro de la Organizaci\u00f3n No Gubernamental; \u00a0 \u00a0<\/p>\n<p>e) Documentos, registros o certificaciones con los cuales el \u00a0extranjero compruebe experiencia previa e idoneidad, concordante con las \u00a0actividades que pretenda desarrollar en nuestro pa\u00eds. \u00a0 \u00a0<\/p>\n<p>7. El extranjero solicitante de Visa Temporal Especial para contraer \u00a0matrimonio deber\u00e1 aportar: \u00a0 \u00a0<\/p>\n<p>a) Carta de solicitud del futuro c\u00f3nyuge colombiano, debidamente \u00a0autenticada ante notario o legalizada ante C\u00f3nsul Colombiano, seg\u00fan el caso, \u00a0indicando d\u00f3nde se realizar\u00e1 el matrimonio; \u00a0 \u00a0<\/p>\n<p>b) Fotocopia autenticada de la c\u00e9dula de ciudadan\u00eda del futuro \u00a0c\u00f3nyuge colombiano. \u00a0 \u00a0<\/p>\n<p>8. El extranjero solicitante de Visa Temporal Especial para \u00a0tr\u00e1mites de adopci\u00f3n, deber\u00e1 aportar: \u00a0 \u00a0<\/p>\n<p>a) Fotocopia de la constancia de asignaci\u00f3n del menor a la familia \u00a0adoptante expedida por el Instituto Colombiano de Bienestar Familiar, ICBF, o la casa de adopci\u00f3n respectiva; \u00a0 \u00a0<\/p>\n<p>b) Fotocopia del documento que acredita la Personar\u00eda Jur\u00eddica de \u00a0la casa de adopci\u00f3n colombiana. Cuando el tr\u00e1mite se efect\u00fae ante el Instituto \u00a0Colombiano de Bienestar Familiar, ICBF, no se \u00a0requerir\u00e1 de este requisito; \u00a0 \u00a0<\/p>\n<p>c) Carta de solicitud de los padres adoptantes; \u00a0 \u00a0<\/p>\n<p>d) Fotocopia del pasaje de salida del pa\u00eds. \u00a0 \u00a0<\/p>\n<p>9. En las ocupaciones o actividades no previstas en el presente \u00a0art\u00edculo, se deber\u00e1 aportar carta explicativa del interesado, anexando los \u00a0documentos que demuestren la conveniencia del ingreso al pa\u00eds y la fotocopia de \u00a0los pasajes de salida del territorio nacional. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 75. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La vigencia de esta visa ser\u00e1 hasta por un (1) a\u00f1o, para m\u00faltiples \u00a0entradas. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0OCTAVA \u00a0 \u00a0<\/p>\n<p>De la visa temporal \u00a0visitante \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 76. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Visitante por primera vez, salvo cuando se trate \u00a0de Visitante para prestar servicios t\u00e9cnicos urgentes, ser\u00e1 otorgada por las \u00a0Oficinas Consulares al extranjero que pretenda ingresar al pa\u00eds sin el \u00e1nimo de \u00a0establecerse en \u00e9l, con el prop\u00f3sito de desarrollar actividades de car\u00e1cter \u00a0period\u00edstico para cubrir un acontecimiento especial, al periodista, reportero, \u00a0camar\u00f3grafo o fot\u00f3grafo o a quien haga parte del equipo period\u00edstico y acredite \u00a0tal calidad; para efectuar contactos y actividades comerciales o empresariales; \u00a0para actividades acad\u00e9micas en seminarios, conferencias, simposios, \u00a0exposiciones, cursos o estudios no regulares, que en todo caso no superen un \u00a0semestre acad\u00e9mico para presentar entrevistas en un proceso de selecci\u00f3n de \u00a0personal, en entidades p\u00fablicas o privadas; para tratamiento m\u00e9dico; para \u00a0eventos deportivos, cient\u00edficos o culturales no remunerados. \u00a0 \u00a0<\/p>\n<p>En todo caso, siempre y cuando no exista v\u00ednculo laboral. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. Igualmente, se podr\u00e1 expedir la Visa Temporal \u00a0Visitante, al extranjero que pretenda ingresar al pa\u00eds para prestar servicios \u00a0t\u00e9cnicos urgentes a entidades p\u00fablicas o privadas, previa presentaci\u00f3n de una \u00a0carta de responsabilidad de la entidad, en la que se justifique la urgencia del \u00a0servicio requerido. \u00a0 \u00a0<\/p>\n<p>S\u00ed la entidad solicitante del servicio considera indispensable la \u00a0permanencia del t\u00e9cnico extranjero por un t\u00e9rmino superior, deber\u00e1 presentar la \u00a0solicitud de Visa Temporal Trabajador, a que se refiere el art\u00edculo 52 del \u00a0presente decreto ante el Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. No se requerir\u00e1 Visa Temporal Visitante, ni Permiso \u00a0de Ingreso, cuando se trate de tr\u00e1nsito por el pa\u00eds hasta por el t\u00e9rmino de 24 \u00a0horas. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 77. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Los nacionales de aquellos pa\u00edses con los cuales Colombia ha \u00a0suscrito convenios sobre exenci\u00f3n de visa no requieren de \u00e9sta para ingresar al \u00a0pa\u00eds en calidad de visitante. Igualmente no requerir\u00e1n de esta visa, los \u00a0nacionales de los pa\u00edses que el Ministerio de Relaciones Exteriores determina \u00a0mediante resoluci\u00f3n. \u00a0 \u00a0<\/p>\n<p>En estos casos se les expedir\u00e1 el Permiso de Ingreso y Permanencia \u00a0de que trata el art\u00edculo 96 y podr\u00e1n, igualmente, desarrollar las actividades \u00a0descritas en el art\u00edculo 76 del presente decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 78. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Visitante se expedir\u00e1 hasta por el t\u00e9rmino m\u00e1ximo \u00a0de ciento ochenta (180) d\u00edas calendario dentro del mismo a\u00f1o calendario y \u00a0permitir\u00e1 a su titular m\u00faltiples entradas, salvo cuando se trate de Visa \u00a0Temporal Visitante para prestar servicios t\u00e9cnicos urgentes, caso en el cual la \u00a0vigencia no podr\u00e1 ser superior a cuarenta y cinco (45) d\u00edas calendario dentro \u00a0del mismo a\u00f1o calendario. \u00a0 \u00a0<\/p>\n<p>En el evento de haberse otorgado esta visa o el permiso de ingreso \u00a0de qu\u00e9 trata el art\u00edculo 96 por un t\u00e9rmino inferior al arriba establecido, el \u00a0Grupo Interno de Trabajo que el Ministro de Relaciones Exteriores determine \u00a0podr\u00e1 expedir nueva visa o nuevo permiso por parte del Departamento \u00a0Administrativo de Seguridad, DAS, hasta completar los cuarenta y cinco (45) d\u00edas \u00a0o los ciento ochenta (180) d\u00edas dentro del mismo a\u00f1o calendario, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>El extranjero podr\u00e1 permanecer en el pa\u00eds durante los cuarenta y \u00a0cinco (45) d\u00edas o ciento ochenta (180) d\u00edas continuos o hacer uso de los \u00a0mismos, en intervalos, dentro del mismo a\u00f1o calendario. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 79. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El solicitante de Visa Temporal Visitante deber\u00e1 presentar adem\u00e1s \u00a0de los requisitos establecidos en el art\u00edculo 22 del presente decreto los \u00a0siguientes: \u00a0 \u00a0<\/p>\n<p>a) Documentos que demuestren la actividad que viene a desarrollar \u00a0en el pa\u00eds; \u00a0 \u00a0<\/p>\n<p>b) Documentos que comprueben que su capacidad econ\u00f3mica es suficiente \u00a0para la(s) actividad(es) que pretenda desarrollar en el pa\u00eds; \u00a0 \u00a0<\/p>\n<p>c) Fotocopia del pasaje de salida del pa\u00eds. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 80. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero, titular de Visa Temporal Visitante o de Permiso de \u00a0Ingreso y Permanencia, no podr\u00e1 solicitar en el territorio nacional la expedici\u00f3n \u00a0de una de las siguientes visas: Visa Temporal Trabajador, salvo lo dispuesto en \u00a0el par\u00e1grafo primero del art\u00edculo 76 del presente decreto, Temporal C\u00f3nyuge o \u00a0Compa\u00f1ero(a) Permanente de Nacional Colombiano, Temporal Religioso, o Temporal \u00a0Especial como cooperante o voluntario de entidad sin \u00e1nimo de lucro u \u00a0Organizaci\u00f3n No Gubernamental o quien haya sido presentado por una Misi\u00f3n \u00a0Diplom\u00e1tica u Organismo Internacional o para contraer matrimonio. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 81. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero que ingrese al pa\u00eds con Visa Temporal Visitante, no podr\u00e1 \u00a0devengar salarios provenientes de personas naturales o jur\u00eddicas establecidas \u00a0en el pa\u00eds, ni podr\u00e1 realizar actividades que est\u00e9n amparadas por otro tipo de \u00a0visa. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0NOVENA \u00a0 \u00a0<\/p>\n<p>De la Visa Temporal \u00a0Refugiado o Asilado \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 82. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa Temporal Refugiado o Asilado podr\u00e1 ser expedida por el \u00a0Grupo Interno de Trabajo que el Ministro de Relaciones Exteriores determine, al \u00a0extranjero as\u00ed calificado por el Ministerio de Relaciones Exteriores, mediante \u00a0resoluci\u00f3n que se expida para tal efecto, y de conformidad con los Tratados o \u00a0Convenios sobre la materia ratificados por el Gobierno Colombiano. \u00a0 \u00a0<\/p>\n<p>Para obtener esta Visa, el interesado, adem\u00e1s de los requisitos \u00a0establecidos en el art\u00edculo 22 del presente decreto, deber\u00e1 anexar fotocopia \u00a0autentica de la resoluci\u00f3n del Ministerio de Relaciones Exteriores, mediante la \u00a0cual se le reconoce la condici\u00f3n de refugiado o asilado. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Esta visa se expedir\u00e1 hasta por el t\u00e9rmino de tres (3) \u00a0a\u00f1os y permitir\u00e1 m\u00faltiples entradas. \u00a0 \u00a0<\/p>\n<p>CAPITULO VII \u00a0 \u00a0<\/p>\n<p>De la Visa de Residente \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 83. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine o las Oficinas Consulares de la Rep\u00fablica, previa \u00a0autorizaci\u00f3n de aquel, podr\u00e1n otorgar Visa de Residente, por t\u00e9rmino indefinido \u00a0y para m\u00faltiples entradas, al extranjero que pretenda establecerse en el pa\u00eds \u00a0de manera definitiva. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 84. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El solicitante de Visa de Residente deber\u00e1 presentar adem\u00e1s de los requisitos \u00a0establecidos en el art\u00edculo 22 del presente decreto, el certificado de \u00a0antecedentes judiciales o de polic\u00eda del \u00faltimo pa\u00eds de domicilio expedido por \u00a0la autoridad competente con una antelaci\u00f3n no mayor a seis (6) meses, excepto \u00a0si es menor de 18 a\u00f1os o mayor de 65 a\u00f1os. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 85. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa de Residente caducar\u00e1 si el extranjero se ausenta del pa\u00eds \u00a0por m\u00e1s de dos (2) a\u00f1os continuos. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0PRIMERA \u00a0 \u00a0<\/p>\n<p>De la Visa de Residente \u00a0como Familiar de Nacional Colombiano \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 86. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. A la luz de lo dispuesto en los art\u00edculos 25, 32 y 33 de la Ley 43 \u00a0de 1993, el Grupo Interno de Trabajo que el Ministro de Relaciones Exteriores \u00a0determine o las Oficinas Consulares, previa autorizaci\u00f3n de aquel, podr\u00e1n \u00a0otorgar Visa de Residente como Familiar de Nacional Colombiano, al colombiano \u00a0por adopci\u00f3n o por nacimiento que hubiere adquirido nacionalidad extranjera \u00a0renunciando a la nacionalidad colombiana. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 87. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para obtener esta Visa, el extranjero, adem\u00e1s de los requisitos establecidos \u00a0en los art\u00edculos 22 y 84 del presente decreto, deber\u00e1 presentar fotocopia de la \u00a0constancia de renuncia a la nacionalidad colombiana o del documento que indique \u00a0la adquisici\u00f3n de otra nacionalidad seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Para acreditar la ocupaci\u00f3n, el extranjero deber\u00e1 \u00a0presentar los documentos que demuestren la actividad a desarrollar en Colombia, \u00a0como independiente o vinculado con entidad p\u00fablica o privada, para lo cual en \u00a0el \u00faltimo caso aportar\u00e1 contrato de trabajo, o documento pertinente, y certificado \u00a0de proporcionalidad expedido por el Ministerio del Trabajo as\u00ed como documentos \u00a0que acrediten su idoneidad. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0SEGUNDA \u00a0 \u00a0<\/p>\n<p>De la Visa de Residente \u00a0Calificado \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 88. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine o las Oficinas Consulares, previa autorizaci\u00f3n de aquel, podr\u00e1n \u00a0otorgar Visa de Residente Calificado al extranjero que haya sido titular de \u00a0Visa Temporal durante cinco (5) a\u00f1os continuos e ininterrumpidos, \u00a0y presente la solicitud por lo menos dentro de los treinta (30) d\u00edas anteriores \u00a0al vencimiento de la visa de la que sea titular, salvo fuerza mayor o caso \u00a0fortuito debidamente comprobados. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. A los titulares de Visa Temporal C\u00f3nyuge o \u00a0Compa\u00f1ero(a) de Nacional Colombiano y Temporal Padre o Madre de Nacional \u00a0Colombiano de que tratan los art\u00edculos 56 y 58 del presente decreto, se les \u00a0podr\u00e1 expedir la Visa de Residente Calificado cuando hayan sido titulares de \u00a0las mismas por un t\u00e9rmino continuo e ininterrumpido \u00a0m\u00ednimo de tres (3) a\u00f1os. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. No podr\u00e1n solicitar Visa de Residente Calificado los \u00a0titulares de Visa: Preferencial; Cortes\u00eda; Negocios; Tripulante; Temporal en \u00a0las categor\u00edas Estudiante, Empresarial, Especial para Tratamiento M\u00e9dico, \u00a0intervenir en procesos administrativos o judiciales, para tr\u00e1mites de adopci\u00f3n; \u00a0Visitante y Turismo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 89. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El solicitante de Visa Residente Calificado, adem\u00e1s de los requisitos \u00a0establecidos en los art\u00edculos 22 y 84 del presente decreto, deber\u00e1 aportar los \u00a0siguientes documentos: \u00a0 \u00a0<\/p>\n<p>a) Certificado de movimiento migratorio expedido por el \u00a0Departamento Administrativo de Seguridad, DAS, con una antelaci\u00f3n no mayor de \u00a030 d\u00edas; \u00a0 \u00a0<\/p>\n<p>b) Documentos que demuestren la actividad a desarrollar en \u00a0Colombia, como independiente o vinculado con entidad p\u00fablica o privada, para lo \u00a0cual en el \u00faltimo caso deber\u00e1 presentar contrato de trabajo, o documento \u00a0pertinente, y certificado de proporcionalidad expedido por el Ministerio del \u00a0Trabajo as\u00ed como documentos que acrediten su idoneidad. \u00a0 \u00a0<\/p>\n<p>SECCION \u00a0TERCERA \u00a0 \u00a0<\/p>\n<p>De la Visa de Residente \u00a0Inversionista \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 90. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para los efectos del presente decreto, consid\u00e9rase inversionista, \u00a0al extranjero que aporte a su nombre una inversi\u00f3n extranjera directa conforme \u00a0con lo previsto en el Estatuto de Inversiones Internacionales y dem\u00e1s normas \u00a0concordantes vigentes al momento de la solicitud, en la cuant\u00eda que determine \u00a0el Ministerio de Relaciones Exteriores, mediante resoluci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. El solicitante de Visa de Residente Inversionista, adem\u00e1s \u00a0de los requisitos establecidos en los art\u00edculos 22 y 84 del presente Decreto, \u00a0deber\u00e1 presentar, certificaci\u00f3n expedida por el Banco de la Rep\u00fablica, en la \u00a0que conste el registro de la inversi\u00f3n a su nombre. \u00a0 \u00a0<\/p>\n<p>CAPITULO VIII \u00a0 \u00a0<\/p>\n<p>De la Visa de Turismo \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 91. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La Visa de Turismo por primera vez ser\u00e1 otorgada por las Oficinas \u00a0Consulares al extranjero que pretenda ingresar al pa\u00eds con el \u00fanico prop\u00f3sito \u00a0de desarrollar actividades de descanso o esparcimiento. Cuando no sea por \u00a0primera vez, igualmente, podr\u00e1 ser otorgada por las Oficinas Consulares o por \u00a0el Grupo de Trabajo que el Ministro de Relaciones Exteriores determine. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Esta Visa se regir\u00e1 por lo dispuesto en los art\u00edculos \u00a077, 78, 79, 80 y 81 del presente decreto. \u00a0 \u00a0<\/p>\n<p>TITULO IV \u00a0 \u00a0<\/p>\n<p>DE LOS BENEFICIARIOS \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 92. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Las visas a que se refiere el presente decreto, salvo las \u00a0excepciones contempladas en el par\u00e1grafo del presente art\u00edculo, podr\u00e1n \u00a0otorgarse por el Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine, o por las Oficinas Consulares en calidad de beneficiario \u00a0al c\u00f3nyuge, compa\u00f1ero(a) permanente, padres e hijos, dependientes \u00a0econ\u00f3micamente del extranjero, a quien se hubiere otorgado una visa, previa \u00a0prueba del v\u00ednculo o parentesco; en este caso la ocupaci\u00f3n del beneficiario \u00a0ser\u00e1 hogar o estudiante y no podr\u00e1 autorizarse ocupaci\u00f3n diferente. \u00a0 \u00a0<\/p>\n<p>La vigencia de la visa otorgada en calidad de beneficiario no podr\u00e1 \u00a0exceder la de la visa otorgada al titular y expirar\u00e1 al mismo tiempo que \u00e9sta, \u00a0sin necesidad de pronunciamiento expreso de la autoridad competente. \u00a0 \u00a0<\/p>\n<p>Si el beneficiario dejase de depender econ\u00f3micamente d el titular o \u00a0pierde su calidad de c\u00f3nyuge o compa\u00f1ero(a) permanente, deber\u00e1 solicitar visa \u00a0como titular en cualquier Oficina Consular de Colombia. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Las Visas de Cortes\u00eda, salvo lo establecido en normas \u00a0especiales, Negocios, Tripulante, Empresarial, Visitante y Turismo no dan lugar \u00a0a la expedici\u00f3n de visas en calidad de Beneficiario. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 93. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La disoluci\u00f3n del v\u00ednculo matrimonial o de la uni\u00f3n singular \u00a0permanente, por fallecimiento del titular de la visa, no implica la cancelaci\u00f3n \u00a0de la visa otorgada a sus beneficiarios. Sin embargo, el beneficiario podr\u00e1 \u00a0solicitar la visa que corresponda en el territorio nacional. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 94. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El solicitante de Visa en calidad de beneficiario, deber\u00e1 \u00a0presentar, adem\u00e1s de los requisitos establecidos en el art\u00edculo 22 del presente \u00a0decreto, los siguientes documentos: \u00a0 \u00a0<\/p>\n<p>a) Registro Civil o documento an\u00e1logo que demuestre el v\u00ednculo o \u00a0parentesco; \u00a0 \u00a0<\/p>\n<p>b) Prueba de la dependencia econ\u00f3mica. \u00a0 \u00a0<\/p>\n<p>c) Nota por la cual el titular de la visa se hace responsable de la \u00a0permanencia del beneficiario y su salida del pa\u00eds; \u00a0 \u00a0<\/p>\n<p>d) Cuando se trate de Visa Temporal por primera vez o de Residente \u00a0Calificado, certificado de antecedentes judiciales cuando se trate de \u00a0beneficiarios mayores de dieciocho (18) a\u00f1os y menores de sesenta y cinco (65) \u00a0a\u00f1os, de conformidad con lo establecido en el art\u00edculo 17 del presente decreto; \u00a0 \u00a0<\/p>\n<p>e) Fotocopia de la visa del titular. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Cuando el Beneficiario sea compa\u00f1ero(a) permanente, se \u00a0adjuntar\u00e1 copia de la providencia judicial mediante la cual se acredite la \u00a0existencia de la uni\u00f3n singular y permanente de hecho. Si la solicitud se \u00a0presenta en el exterior, se aceptar\u00e1 el documento que compruebe la convivencia \u00a0o uni\u00f3n marital de hecho en dicho pa\u00eds. En todo caso para la solicitud de nueva \u00a0visa en el Grupo Interno de Trabajo que el Ministro de Relaciones Exteriores \u00a0determine, se deber\u00e1 presentar la respectiva providencia judicial. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 95. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Si la solicitud de Visa en calidad de beneficiario se efect\u00faa ante \u00a0una Oficina Consular diferente a la que expidi\u00f3 la visa al titular, la Oficina \u00a0Consular deber\u00e1 solicitar previamente autorizaci\u00f3n al Grupo Interno de Trabajo \u00a0que el Ministro de Relaciones Exteriores determine. \u00a0 \u00a0<\/p>\n<p>TITULO V \u00a0 \u00a0<\/p>\n<p>DEL PERMISO DE INGRESO Y PERMANENCIA \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 96. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Departamento Administrativo de Seguridad, DAS, podr\u00e1 otorgar \u00a0permiso de ingreso y permanencia, a los visitantes extranjeros, cuando el \u00a0Ministerio de Relaciones Exteriores no exija visa para su entrada al pa\u00eds, \u00a0previa presentaci\u00f3n del pasaje de salida. Dicho permiso se regir\u00e1 por las \u00a0disposiciones previstas en los art\u00edculos 76 y siguientes consagrados en el \u00a0presente decreto para la Visa de Visitante y en el art\u00edculo 91 para la Visa de \u00a0Turismo. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Igualmente, se podr\u00e1 expedir Permiso de Ingreso y \u00a0Permanencia, al extranjero que pretenda ingresar al pa\u00eds para prestar servicios \u00a0t\u00e9cnicos urgentes a entidades p\u00fablicas o privadas, previa presentaci\u00f3n de una \u00a0carta de responsabilidad de la entidad, en la que se justifique la urgencia del \u00a0servicio requerido. En este caso el Permiso de Ingreso y Permanencia tendr\u00e1 una \u00a0vigencia de hasta cuarenta y cinco (45) d\u00edas, improrrogables dentro del mismo \u00a0a\u00f1o calendario. \u00a0 \u00a0<\/p>\n<p>Si la entidad solicitante del servicio considera indispensable la \u00a0permanencia del t\u00e9cnico extranjero por un t\u00e9rmino superior al autorizado, \u00a0deber\u00e1 presentar solicitud de Visa Temporal Trabajador, ante el Grupo Interno \u00a0de Trabajo que el Ministro de Relaciones Exteriores determine. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 97. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Las personas que deban desembarcar en el territorio nacional para \u00a0dirigirse a otro pa\u00eds de destino, s\u00f3lo requerir\u00e1n el permiso de ingreso \u00a0expedido por la autoridad migratoria, por el t\u00e9rmino necesario. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 98. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. En cualquier momento la autoridad migratoria podr\u00e1 limitar la \u00a0permanencia autorizada o revocar el permiso de ingreso. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 99. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Salvo lo dispuesto en Tratados Internacionales, cuando se trate de \u00a0tr\u00e1nsito fronterizo, para el ingreso de extranjero nacional o residente de pa\u00eds \u00a0vecino s\u00f3lo se requerir\u00e1 el correspondiente permiso de ingreso otorgado por la \u00a0autoridad migratoria, previa presentaci\u00f3n del documento de identificaci\u00f3n \u00a0v\u00e1lido en su pa\u00eds. \u00a0 \u00a0<\/p>\n<p>Para los efectos del presente decreto, se entiende por tr\u00e1nsito \u00a0fronterizo el paso circunstancial de personas residentes en las localidades \u00a0fronterizas a Colombia, que autoriza al extranjero para movilizarse dentro de \u00a0la zona fronteriza colombiana y por los sitios determinados por el Gobierno \u00a0Nacional. \u00a0 \u00a0<\/p>\n<p>TITULO VI \u00a0 \u00a0<\/p>\n<p>DEL PERMISO DE INGRESO DE GRUPO EN TRANSITO \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 100. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Departamento Administrativo de Seguridad, DAS, podr\u00e1 otorgar \u00a0permiso de ingreso necesario por un t\u00e9rmino hasta de 72 horas a los pasajeros \u00a0de grupo en tr\u00e1nsito de buques de cruceros tur\u00edsticos, que visiten los puertos \u00a0mar\u00edtimos y fluviales que reembarquen en el mismo nav\u00edo. \u00a0 \u00a0<\/p>\n<p>Para tal efecto, la autoridad migratoria del puerto deber\u00e1 recibir \u00a0con setenta y dos (72) horas de anticipaci\u00f3n por parte del Capit\u00e1n del Nav\u00edo o \u00a0de la agencia mar\u00edtima responsable, la lista de los pasajeros y los tripulantes \u00a0que desembarcar\u00e1n, con indicaci\u00f3n del pasaporte, o documento an\u00e1logo v\u00e1lido, de \u00a0cada uno de ellos y el t\u00e9rmino de la visita. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Enti\u00e9ndase como buques en crucero, aquellos de traves\u00eda \u00a0internacional, cuyos pasajeros alojados a bordo participan en un programa de \u00a0grupo, que tienen previstas escalas tur\u00edsticas temporales en uno o m\u00e1s puertos \u00a0diferentes. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 101. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para el permiso de ingreso de pasajeros de grupo en tr\u00e1nsito a que \u00a0se refiere el art\u00edculo anterior, no se requerir\u00e1 visa y\/o diligenciar tarjeta \u00a0migratoria por parte del pasajero, ni anotaci \u00f3n o estampado de sello de entrada o salida en su pasaporte \u00a0o documento an\u00e1logo v\u00e1lido. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 102. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Departamento Administrativo de Seguridad, DAS, podr\u00e1 otorgar \u00a0igualmente permiso por el t\u00e9rmino estrictamente necesario a pasajeros de grupo \u00a0en tr\u00e1nsito de buques en cruceros tur\u00edsticos que desembarquen en los puertos \u00a0mar\u00edtimos y fluviales para dirigirse a otro pa\u00eds de destino por el puerto a\u00e9reo \u00a0de la misma ciudad, y a los pasajeros de vuelos internacionales que arriben al \u00a0puerto a\u00e9reo para embarcarse en los buques de cruceros tur\u00edsticos. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 103. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Departamento Administrativo de Seguridad, DAS, en colaboraci\u00f3n \u00a0con las dem\u00e1s autoridades de polic\u00eda adoptar\u00e1n, las medidas de seguridad que \u00a0sean necesarias para garantizar la salida del puerto respectivo de los \u00a0pasajeros conforme al permiso otorgado. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 104. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. En todos los casos los pasajeros deber\u00e1n presentar al ingreso por \u00a0el puerto mar\u00edtimo o a\u00e9reo, una credencial expedida por la l\u00ednea mar\u00edtima, que \u00a0los acredite como integrantes o pasajeros del grupo en tr\u00e1nsito, en el cual \u00a0consten sus datos personales, domicilio y nacionalidad. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 105. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. En los casos no previstos en este decreto, y en todo lo que se \u00a0relacione con buques de cruceros tur\u00edsticos, las autoridades portuarias deber\u00e1n \u00a0remitirse a las disposiciones legales vigentes en especial, a la Ley 17 de \u00a01991. \u00a0 \u00a0<\/p>\n<p>TITULO VII \u00a0 \u00a0<\/p>\n<p>DEL CONTROL MIGRATORIO \u00a0 \u00a0<\/p>\n<p>CAPITULO I \u00a0 \u00a0<\/p>\n<p>Del Ingreso \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 106. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La persona que pretenda ingresar o salir del territorio nacional \u00a0deber\u00e1 presentarse ante la autoridad migratoria con su pasaporte vigente, \u00a0documento de viaje o documento de identidad seg\u00fan el caso y la visa \u00a0correspondiente cuando sea exigible. \u00a0 \u00a0<\/p>\n<p>El proceso migratorio deber\u00e1 realizarse en los siguientes lugares \u00a0habilitados: \u00a0 \u00a0<\/p>\n<p>1. Puertos A\u00e9reos: Barranquilla, Bucaramanga, Cali, Cartagena, \u00a0C\u00facuta, Leticia, Medell\u00edn, Neiva, Pereira, Puerto As\u00eds, Bogot\u00e1, San Andr\u00e9s y \u00a0Santa Marta. \u00a0 \u00a0<\/p>\n<p>2. Puertos Mar\u00edtimos: Barranquilla, Buenaventura, Cartagena, Puerto \u00a0Bol\u00edvar, Riohacha, Santa Marta, San Andr\u00e9s, Turbo, Tumaco y Ciudad Mutis (Bah\u00eda \u00a0Solano.) \u00a0 \u00a0<\/p>\n<p>3. Puertos Fluviales: Arauca, Leticia, Puerto As\u00eds y Puerto \u00a0Carre\u00f1o. \u00a0 \u00a0<\/p>\n<p>4. Puertos Terrestres: Arauca, C\u00facuta, Ipiales, Maicao, Puerto \u00a0As\u00eds, Puerto Carre\u00f1o, Capurgan\u00e1, Mit\u00fa, Puert o Santander, Puerto In\u00edrida, \u00a0y San Miguel. \u00a0 \u00a0<\/p>\n<p>5. Los dem\u00e1s que establezca o modifique el Gobierno Nacional. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 107. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Los lugares habilitados podr\u00e1n ser cerrados al tr\u00e1nsito de personas \u00a0en forma temporal, cuando ocurran circunstancias que aconsejen dicha medida. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 108. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Todas las personas ser\u00e1n \u00a0sometidas al momento de su ingreso al pa\u00eds, al correspondiente control \u00a0migratorio que estar\u00e1 a carga del Departamento Administrativo de Seguridad, \u00a0DAS, a fin de determinar la regularidad de su ingreso. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 109. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Consid\u00e9rase irregular el ingreso al territorio nacional en los \u00a0siguientes casos: \u00a0 \u00a0<\/p>\n<p>1. Ingresar al pa\u00eds por lugar no habilitado. \u00a0 \u00a0<\/p>\n<p>2. Ingresar al pa\u00eds por lugar habilitado pero evadiendo u omitiendo \u00a0el control migratorio. \u00a0 \u00a0<\/p>\n<p>3. Ingresar al pa\u00eds sin la correspondiente documentaci\u00f3n o con \u00a0documentaci\u00f3n falsa. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 110. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Consid\u00e9rase irregular la permanencia en el territorio nacional \u00a0cuando se dan los supuestos mencionados en el art\u00edculo anterior y cuando el \u00a0extranjero, habiendo ingresado legalmente, permanece en el pa\u00eds una vez vencido \u00a0el t\u00e9rmino autorizado. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 111. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Director del Departamento Administrativo de Seguridad, DAS, \u00a0podr\u00e1 delegar en otros organismos de seguridad del Estado, previa celebraci\u00f3n \u00a0de los convenios a que hubiere lugar, el cumplimiento de la funci\u00f3n de control \u00a0migratorio, en aquellos lugares en los cuales el Departamento Administrativo de \u00a0Seguridad, DAS, no cuenta con Direcciones Seccionales o cuando la dificultad en \u00a0el desarrollo de los procedimientos migratorios as\u00ed lo amerite. \u00a0 \u00a0<\/p>\n<p>CAPITULO II \u00a0 \u00a0<\/p>\n<p>De la inadmisi\u00f3n o rechazo \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 112. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La inadmisi\u00f3n o rechazo es la decisi\u00f3n \u00a0administrativa por la cual la autoridad migratoria, al efectuar el control de \u00a0migraci\u00f3n, le niega el ingreso a un extranjero por cualquiera de las causales \u00a0se\u00f1aladas en el art\u00edculo siguiente, ordenando su inmediato retorno al pa\u00eds de \u00a0embarque o de origen o a un tercer pa\u00eds que lo admita. Contra esta decisi\u00f3n no \u00a0proceden los recursos de la v\u00eda gubernativa. \u00a0 \u00a0<\/p>\n<p>Cuando no fuere posible proceder a la ejecuci\u00f3n de la inadmisi\u00f3n o rechazo en forma inmediata, la autoridad \u00a0migratoria podr\u00e1 retener al extranjero hasta por treinta y seis (36) horas, \u00a0vencidas las cuales ser\u00e1 puesto a disposici\u00f3n del medio de transporte que \u00a0deber\u00e1 regresarlo a su lugar procedencia. \u00a0 \u00a0<\/p>\n<p>La autoridad migratoria podr\u00e1 igualmente fijar al extranjero un \u00a0plazo prudencial no superior a setenta y dos (72) horas para que abandone el \u00a0pa\u00eds. \u00a0 \u00a0<\/p>\n<p>En ning\u00fan caso se podr\u00e1 proceder sin que medie la intervenci\u00f3n del \u00a0Director del Departamento Administrativo de Seguridad-DAS-o sus delegados. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 113. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Ning\u00fan extranjero podr\u00e1 ingresar al territorio nacional si se \u00a0encuentra comprendido dentro de alguna de las siguientes situaciones: \u00a0 \u00a0<\/p>\n<p>1. Padecer enfermedad infecto-contangiosa \u00a0o estar afectado por cualquier tipo de alineaci\u00f3n mental de la que pueda \u00a0derivarse un riesgo para la salud p\u00fablica y el orden social. \u00a0 \u00a0<\/p>\n<p>2. Carecer de recursos econ\u00f3micos que garanticen la subsistencia y \u00a0la posibilidad de desarrollar las actividades declaradas o del tiquete de \u00a0salida del territorio colombiano, cuando se trate de extranjeros con permiso de \u00a0ingreso o visa visitante. \u00a0 \u00a0<\/p>\n<p>3. Traficar o haber traficado con estupefacientes, drogas, \u00a0alucin\u00f3genas o cualquier otra sustancia similar. \u00a0 \u00a0<\/p>\n<p>4. Tener procesos pendientes por delitos con penas privativas de la \u00a0libertad de dos (2) o m\u00e1s a\u00f1os, y\/o registrar conductas en el exterior que \u00a0puedan comprometer la seguridad del Estado o poner en peligro la tranquilidad \u00a0social. \u00a0 \u00a0<\/p>\n<p>5. Haber sido expulsado del pa\u00eds, salvo que con posterioridad a \u00a0dicha medida le haya sido concedida visa. \u00a0 \u00a0<\/p>\n<p>6. Haber sido extraditado del pa\u00eds salvo que compruebe la \u00a0absoluci\u00f3n de los delitos imputados. \u00a0 \u00a0<\/p>\n<p>7. No presentar visa cuando se requiera, de acuerdo con las \u00a0disposiciones de este decreto. \u00a0 \u00a0<\/p>\n<p>8 Estar registrado en los archivos especializados de la polic\u00eda \u00a0internacional. \u00a0 \u00a0<\/p>\n<p>9. Haber sido deportado y pretender el ingreso al pa\u00eds antes del \u00a0t\u00e9rmino establecido en la providencia correspondiente. \u00a0 \u00a0<\/p>\n<p>10. Carecer de profesi\u00f3n, ocupaci\u00f3n, industria, oficio u otro medio \u00a0l\u00edcito de vida o cuando por falta de h\u00e1bito de trabajo, ebriedad habitual o \u00a0vagancia se considera inconveniente su ingreso al pa\u00eds. \u00a0 \u00a0<\/p>\n<p>11. Participar directa o indirectamente en el tr\u00e1fico de personas o \u00a0de sus \u00f3rganos. \u00a0 \u00a0<\/p>\n<p>12. Pretender ingresar al pa\u00eds con documentos falsos o sin la \u00a0documentaci\u00f3n legalmente exigida. \u00a0 \u00a0<\/p>\n<p>13. Haber incurrido en conductas que, a juicio de la autoridad \u00a0migra toria, califican al extranjero como peligroso \u00a0para la seguridad nacional o la tranquilidad social. \u00a0 \u00a0<\/p>\n<p>14. Haber salido del territorio nacional evadiendo el control \u00a0migratorio. \u00a0 \u00a0<\/p>\n<p>CAPITULO III \u00a0 \u00a0<\/p>\n<p>Del registro, \u00a0documentaci\u00f3n y control \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 114. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Los titulares de visa cuya vigencia sea superior a seis (6) meses, \u00a0as\u00ed como los beneficiarios de las mismas en los t\u00e9rminos del art\u00edculo 92 y \u00a0siguientes del presente decreto, salvo los titulares de Visa Preferencial y \u00a0Temporal Empresarial, deber\u00e1n inscribirse en el registro de extranjeros que se \u00a0lleva en el Departamento Administrativo de Seguridad-DAS-, dentro del plazo de \u00a0sesenta (60) d\u00edas calendario siguientes contados a partir de su ingreso al \u00a0pa\u00eds, o de la fecha de expedici\u00f3n de la visa si esta se obtuvo dentro del \u00a0territorio nacional. \u00a0 \u00a0<\/p>\n<p>El extranjero de visa cuya vigencia sea inferior a seis (6) meses, \u00a0as\u00ed como el titular de Visa Temporal Empresarial, podr\u00e1 inscribirse en el \u00a0registro de extranjeros, si as\u00ed lo desea. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Para los efectos previstos en este art\u00edculo el \u00a0extranjero podr\u00e1 solicitar su registro en cualquier momento sin perjuicio a las \u00a0sanciones pecuniarias a que hubiere lugar. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 115. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El registro de extranjeros deber\u00e1 contener los datos biogr\u00e1ficos, \u00a0as\u00ed como la informaci\u00f3n que determine las autoridades de migraci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 116. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Tienen car\u00e1cter reservado en los archivos del Departamento \u00a0Administrativo de Seguridad, DAS, el registro de extranjeros, los documentos \u00a0pertenecientes a la informaci\u00f3n de inteligencia e investigaciones de car\u00e1cter \u00a0migratorio o para fines judiciales y la informaci\u00f3n del movimiento migratorio \u00a0tanto de nacionales como de extranjeros, salvo cuando sean solicitados por: \u00a0 \u00a0<\/p>\n<p>a) Modificado por el \u00a0Decreto 1384 de 2002, \u00a0art\u00edculo 1. El titular del respectivo registro o por sus parientes hasta \u00a0el cuarto grado de consanguinidad, segundo de afinidad y primero civil o por el \u00a0c\u00f3nyuge o compa\u00f1ero permanente debidamente acreditados. \u00a0 \u00a0<\/p>\n<p>Texto inicial del literal \u00a0a). \u201cEl titular del respectivo \u00a0registro;\u201d. \u00a0 \u00a0<\/p>\n<p>b) Los funcionarios judiciales y de polic\u00eda que adelanten \u00a0investigaciones respecto de la persona registrada; \u00a0 \u00a0<\/p>\n<p>c) Las autoridades y entidades que cumplan funciones \u00a0administrativas y que necesiten conocer los antecedentes de las personas \u00a0registradas para efectos oficiales. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 117. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Con base en el registro de extranjeros, el Departamento Administrativo \u00a0de Seguridad-DAS-, otorgar\u00e1 un documento de identidad, denominado c\u00e9dula de \u00a0extranjer\u00eda, para los mayores de dieciocho (18) a\u00f1os, con una vigencia igual a \u00a0la duraci\u00f3n de la visa. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. Para la expedici\u00f3n de dicho documento, el interesado \u00a0deber\u00e1 presentar su pasaporte vigente o documento de viaje con la visa \u00a0respectiva y suministrar l os datos y documentos necesarios para su \u00a0elaboraci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. El extranjero, al cumplir la edad de dieciocho (18) \u00a0a\u00f1os, deber\u00e1 presentarse al Departamento Administrativa de Seguridad,-DAS-, \u00a0dentro de los sesenta (60) d\u00edas calendario siguientes para obtener la c\u00e9dula de \u00a0extranjer\u00eda. \u00a0 \u00a0<\/p>\n<p>\u00a0Art\u00edculo 118. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Los titulares de visa \u00a0preferencial diplom\u00e1ticas oficial y de servicio, se identificar\u00e1n con el carn\u00e9 \u00a0que expide la Direcci\u00f3n del Protocolo del Ministerio de Relaciones Exteriores. \u00a0 \u00a0<\/p>\n<p>Los titulares de las dem\u00e1s visas que deban registrarse ante el \u00a0Departamento Administrativo de Seguridad, DAS, se identificar\u00e1n dentro del \u00a0territorio nacional con la respectiva c\u00e9dula de extranjer\u00eda. Los dem\u00e1s se \u00a0identificar\u00e1n con el pasaporte vigente. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Adicionado por el Decreto 1384 de 2002, \u00a0art\u00edculo 2. La c\u00e9dula de extranjer\u00eda expedida a quienes se \u00a0les haya otorgado visa de residente, deber\u00e1 ser renovada cada cinco (5) a\u00f1os. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 119. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero que deba registrarse, comunicar\u00e1 al Departamento \u00a0Administrativo de Seguridad, DAS, y al Grupo Interno de Trabajo que el Ministro \u00a0de Relaciones Exteriores determine, sobre cualquier cambio de residencia o \u00a0domicilio dentro de los sesenta (60) d\u00edas calendario siguientes a la ocurrencia \u00a0del hecho. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 120. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Departamento Administrativo de Seguridad, DAS, podr\u00e1 expedir a \u00a0los extranjeros salvoconductos que ser\u00e1n de dos clases: \u00a0 \u00a0<\/p>\n<p>1. Salvoconducto para salir del pa\u00eds, v\u00e1lido hasta por treinta (30) \u00a0d\u00edas calendario en los siguientes casos: \u00a0 \u00a0<\/p>\n<p>a) Cuando el extranjero incurra en permanencia irregular, previo \u00a0cumplimiento de las sanciones pecuniarias a que hubiere lugar. \u00a0 \u00a0<\/p>\n<p>b) Cuando el extranjero sea deportado o expulsado; \u00a0 \u00a0<\/p>\n<p>c) Cuando al extranjero se le haya cancelado su visa o \u00e9sta haya \u00a0caducado salvo lo dispuesto para este caso en el par\u00e1grafo segundo del art\u00edculo \u00a013 del presente decreto. Igualmente se expedir\u00e1 este salvoconducto cuando al \u00a0extranjero le sea revocado el permiso de ingreso. \u00a0 \u00a0<\/p>\n<p>d) Cuando la solicitud de visa ha sido negada al extranjero por el \u00a0grupo Interno de Trabajo que el Ministro de Relaciones Exteriores determine. \u00a0 \u00a0<\/p>\n<p>2. Salvoconducto para permanecer en el pa\u00eds, en los siguientes \u00a0casos: \u00a0 \u00a0<\/p>\n<p>a) Al extranjero que deba solicitar visa o su cambio conforme a las \u00a0disposiciones de este decreto, hasta por sesenta (60) d\u00edas calendario, \u00a0prorrogables hasta por treinta (30) d\u00edas calendario m\u00e1s, cuando dicho tr\u00e1mite \u00a0pueda realizarse en el territorio nacional; \u00a0 \u00a0<\/p>\n<p>b) Al extranjero que deba permanecer en el territorio nacional en \u00a0libertad provisional o condicional, o por orden de autoridad competente, por \u00a0sesenta (60) d\u00edas calendario, prorrogables hasta tanto se le defina la \u00a0situaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 121. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Cuando el Min isterio \u00a0de Relaciones Exteriores no tenga oportunidad de hacerlo, el Departamento \u00a0Administrativo de Seguridad-DAS-, podr\u00e1 hacer la anotaci\u00f3n de caducidad o \u00a0cancelaci\u00f3n, seg\u00fan el caso, sobre la visa que aparezca en el pasaporte del \u00a0extranjero, de acuerdo con lo establecido en el art\u00edculo 13 del presente \u00a0decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 122. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Las autoridades judiciales, administrativas y de polic\u00eda, \u00a0comunicar\u00e1n al Departamento Administrativo de Seguridad-DAS-, y al Grupo \u00a0Interno de Trabajo que el Ministro de Relaciones Exteriores determine, la \u00a0iniciaci\u00f3n de procesos contra extranjeros, los cambios de radicaci\u00f3n y el fallo \u00a0correspondiente. As\u00ed mismo, el Ministerio de Justicia y del Derecho comunicar\u00e1 \u00a0sobre la expedici\u00f3n de resoluciones de extradici\u00f3n. \u00a0 \u00a0<\/p>\n<p>Los directores de centro carcelarios comunicar\u00e1n al Departamento \u00a0Administrativo de Seguridad-DAS-el ingreso o salida de extranjeros del centro \u00a0carcelario respectivo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 123. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Todo empleador de un extranjero deber\u00e1 exigirle la presentaci\u00f3n de \u00a0la c\u00e9dula de extranjer\u00eda cuando corresponda y de acuerdo con lo establecido en \u00a0el presente Decreto, e informar al Departamento Administrativo de Seguridad-DAS\u2011, sobre su vinculaci\u00f3n, dentro de los sesenta \u00a0(60) d\u00edas calendario siguientes a la iniciaci\u00f3n de labores o estudios. Se \u00a0except\u00faa de este \u00faltimo requisito a los contratantes o empresarios de \u00a0espect\u00e1culos p\u00fablicos, culturales o deportivos, cuando la permanencia en el \u00a0territorio nacional se limite a las respectivas presentaciones, en cuyo caso \u00a0exigir\u00e1n la visa correspondiente e informar\u00e1n al Departamento Administrativo de \u00a0Seguridad-DAS\u2011, con antelaci\u00f3n a la realizaci\u00f3n \u00a0del espect\u00e1culo. \u00a0 \u00a0<\/p>\n<p>No obstante, cuando se trate de extranjeros cuya situaci\u00f3n no est\u00e9 \u00a0prevista en el inciso anterior, el empleador, contratante o entidad p\u00fablica o \u00a0privada que vincula al extranjero, deber\u00e1 exigir la presentaci\u00f3n de la \u00a0respectiva visa e informar al Departamento Administrativo de Seguridad, DAS, \u00a0dentro de los sesenta (60) d\u00edas calendario siguientes a la iniciaci\u00f3n de \u00a0labores. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 124. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. En caso de que la visa haya sido otorgada al titular en \u00a0consideraci\u00f3n de la existencia de un contrato con entidad p\u00fablica o privada, o nominaci\u00f3n \u00a0por entidad p\u00fablica, y que \u00e9sta deba registrarse, la entidad nominadora o \u00a0contratante, seg\u00fan sea el caso, deber\u00e1 comunicar por escrito al Departamento \u00a0Administrativo de Seguridad-DAS\u2011, la \u00a0terminaci\u00f3n del contrato o la desvinculaci\u00f3n, dentro de los sesenta (60) d\u00edas \u00a0calendario siguientes a su ocurrencia. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 125. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero deber\u00e1 ejercer la profesi\u00f3n, oficio actividad u \u00a0ocupaci\u00f3n autorizada en la visa. El Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine, podr\u00e1 efectuar su cambio, previo el \u00a0cumplimiento de los requisitos establecidos para el efecto de acuerdo con lo \u00a0estipulado en el art\u00edculo 153 del presente Decreto. Dicho cambio de ber\u00e1 ser comunicado por el extranjero en forma escrita al \u00a0Departamento Administrativo de Seguridad, DAS, dentro de los sesenta (60) d\u00edas \u00a0calendario, siguientes al mismo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 126. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. En hoteles, pensiones, residencias, apartahoteles \u00a0o sitios de hospedaje en general, se llevar\u00e1 un registro de extranjeros en el \u00a0cual consten los siguientes datos: nombres y apellidos, nacionalidad, documento \u00a0de identidad, lugar de procedencia y destino. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Estos \u00a0establecimientos enviar\u00e1n diariamente al Departamento Administrativo de \u00a0Seguridad-DAS\u2011, el registro de extranjeros, sin \u00a0perjuicio de la revisi\u00f3n que puedan efectuar en cualquier momento las \u00a0autoridades de migraci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 127. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Toda persona deber\u00e1 presentarse personalmente ante las autoridades \u00a0migratorias al ser requerido mediante escrito por el Director del Departamento \u00a0Administrativo de Seguridad, DAS, o por sus delegados, en los t\u00e9rminos \u00a0se\u00f1alados en la correspondiente citaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>CAPITULO IV \u00a0 \u00a0<\/p>\n<p>Del control sobre medios \u00a0de transporte internacional \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 128. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para los fines del presente Decreto, se consideran empresas \u00a0transportadoras o medios de transporte internacional, las personas naturales o \u00a0jur\u00eddicas, nacionales o extranjeras que lleven a cabo el transporte \u00a0internacional de personas y\/o carga, v\u00eda a\u00e9rea, mar\u00edtima, fluvial o terrestre. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 129. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Todos los medios de transporte internacional que lleguen al \u00a0territorio nacional o salgan de \u00e9l, quedar\u00e1n sometidos al control de las \u00a0autoridades migratorias, con el objeto de que se realice la revisi\u00f3n de los \u00a0documentos exigibles por este Decreto a los tripulantes y pasajeros que \u00a0transporten. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 130. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Capit\u00e1n, Comandante o responsable de un medio de transporte \u00a0internacional a\u00e9reo, mar\u00edtimo, fluvial o terrestre y de las empresas, compa\u00f1\u00edas \u00a0o agencias consignatarias de un medio de transporte, ser\u00e1n responsables \u00a0solidariamente de la conducci\u00f3n y transporte de pasajeros y tripulantes en \u00a0condiciones reglamentarias, debiendo para tal efecto cumplir con las \u00a0disposiciones de este decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 131. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La inspecci\u00f3n y control migratorio de los pasajeros y tripulantes \u00a0de un medio de transporte mar\u00edtimo o de una embarcaci\u00f3n pesquera, se har\u00e1 a su \u00a0arribo a bordo de la nave o en lugar especialmente habilitado para dichos \u00a0efectos. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 132. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Si al efectuarse el control de entrada la autoridad migratoria \u00a0procede al rechazo o inadmisi\u00f3n de un pasajero o \u00a0tripulante, seg\u00fan las causales establecidas en este Decreto, la empresa \u00a0transportadora, o embarcaci\u00f3n pesquera o en su defecto la agencia propietaria o \u00a0consignataria, o su representante, quedar\u00e1 obligada a retornarlo por su cuenta \u00a0al pa\u00eds de procedenci a o de origen, o a un tercer \u00a0pa\u00eds que lo acepte. \u00a0 \u00a0<\/p>\n<p>De no ser posible el retorno inmediato, los responsables asumir\u00e1n \u00a0los gastos de permanencia que se generen. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 133. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Las empresas de transporte internacional, sus agencias o \u00a0representantes deber\u00e1n: \u00a0 \u00a0<\/p>\n<p>1. Presentar la lista de pasajeros y tripulantes oportunamente, \u00a0incluyendo la informaci\u00f3n que se establezca por v\u00eda reglamentaria. \u00a0 \u00a0<\/p>\n<p>2. No transportar pasajeros sin la presentaci\u00f3n de la documentaci\u00f3n \u00a0requerida y con el visado cuando as\u00ed corresponda. \u00a0 \u00a0<\/p>\n<p>3. Velar porque los tripulantes y\/o personal de la dotaci\u00f3n del \u00a0medio de transporte no permanezcan en el pa\u00eds sin la debida autorizaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>4. Poner a disposici\u00f3n de la autoridad migratoria competente y \u00a0entregar la documentaci\u00f3n correspondiente de los extranjeros o nacionales, \u00a0deportados o devueltos que arriben al pa\u00eds. \u00a0 \u00a0<\/p>\n<p>5. No permitir el desembarco de pasajeros en una escala t\u00e9cnica, \u00a0salvo que se encuentren expresamente autorizados por la autoridad migratoria. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 134. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Departamento Administrativo de Seguridad-DAS\u2011, \u00a0podr\u00e1 celebrar acuerdos con las empresas transportadoras con el objeto de que \u00a0\u00e9stas transporten a extranjeros afectados con medida de deportaci\u00f3n, expulsi\u00f3n \u00a0o cancelaci\u00f3n de visa. \u00a0 \u00a0<\/p>\n<p>CAPITULO V \u00a0 \u00a0<\/p>\n<p>De la salida \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 135. Derogado \u00a0por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para salir del territorio nacional, las personas deber\u00e1n presentar \u00a0a las autoridades migratorias: \u00a0 \u00a0<\/p>\n<p>1. Pasaporte vigente o documento de viaje v\u00e1lido que lo reemplace o \u00a0documento de identidad, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>2. Visa o permiso vigente, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>3. C\u00e9dula de ciudadan\u00eda para los nacionales colombianos, o C\u00e9dula \u00a0de extranjer\u00eda vigente para los extranjeros, cuando as\u00ed corresponda, seg\u00fan el \u00a0caso. \u00a0 \u00a0<\/p>\n<p>4. Salvoconducto en los casos establecidos en este Decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 136. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Con excepci\u00f3n de los visitantes, la salida del territorio nacional \u00a0de los menores extranjeros se regir\u00e1 por lo establecido en el Decreto 2737 de 1989, o la norma que lo reemplace, \u00a0y dem\u00e1s disposiciones complementarias. \u00a0 \u00a0<\/p>\n<p>T I T U L O\u00a0 V I I I \u00a0 \u00a0<\/p>\n<p>DE LAS SANCIONES \u00a0 \u00a0<\/p>\n<p>CAPITULO I \u00a0 \u00a0<\/p>\n<p>De las multas \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 137. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Director del Departamento Administrativo de Seguridad-DAS\u2011, o sus delegados debidamente autorizados, podr\u00e1 \u00a0imponer las sanciones descritas a continuaci\u00f3n, mediante resoluci\u00f3n motivada \u00a0contra la cual proceden los recursos de la v\u00eda gubernativa en el efecto \u00a0suspensivo. \u00a0 \u00a0<\/p>\n<p>1. Multas de medio (1\/2) hasta cinco (5) veces el salario m\u00ednimo \u00a0legal mensual vigente, a quienes incurran en las siguientes faltas: \u00a0 \u00a0<\/p>\n<p>a) No dar aviso del cambio de residencia, domicilio u ocupaci\u00f3n, \u00a0dentro de los sesenta (60) d\u00edas calendario siguientes; \u00a0 \u00a0<\/p>\n<p>b) No presentarse al registro cuando tuviere la obligaci\u00f3n de \u00a0hacerlo dentro de los sesenta (60) d\u00edas calendario siguientes al ingreso al \u00a0pa\u00eds o a la expedici\u00f3n de la visa, seg\u00fan corresponda; \u00a0 \u00a0<\/p>\n<p>c) Negarse reiteradamente a presentarse, a pesar de haber sido \u00a0requerido por escrito; \u00a0 \u00a0<\/p>\n<p>d) Incurrir en permanencia irregular; \u00a0 \u00a0<\/p>\n<p>e) No solicitar el salvoconducto cuando se requiera. \u00a0 \u00a0<\/p>\n<p>f) No solicitar C\u00e9dula de Extranjer\u00eda dentro de los sesenta (60) \u00a0d\u00edas calendario siguientes al cumplimiento de la edad exigida en este Decreto. \u00a0 \u00a0<\/p>\n<p>g) No renovar C\u00e9dula de Extranjer\u00eda dentro de los sesenta (60) d\u00edas \u00a0siguientes a su vencimiento; \u00a0 \u00a0<\/p>\n<p>h) Para los due\u00f1os o administradores de hoteles, pensiones, \u00a0residencias, apartahoteles o sitios de hospedaje en \u00a0general, por incumplir alguna de las obligaciones establecidas en este Decreto; \u00a0 \u00a0<\/p>\n<p>i) Ingresar o salir del pa\u00eds sin el cumplimiento de los requisitos \u00a0legales; \u00a0 \u00a0<\/p>\n<p>j) Ejercer profesi\u00f3n, ocupaci\u00f3n u oficio distinto al autorizado, \u00a0excepto lo dispuesto en los art\u00edculos 65 y 153 del presente Decreto; \u00a0 \u00a0<\/p>\n<p>k) Desarrollar actividades remuneradas sin estar autorizado para \u00a0ello; \u00a0 \u00a0<\/p>\n<p>l) Celebrar contratos comerciales con extranjeros sin el \u00a0cumplimiento de los requisitos legales. \u00a0 \u00a0<\/p>\n<p>m) Facilitar la obtenci\u00f3n de visas, mediante simulaci\u00f3n de alg\u00fan \u00a0tipo de contrato; \u00a0 \u00a0<\/p>\n<p>n) Para las entidades religiosas, no informar dentro de los sesenta \u00a0(60) d\u00edas calendario siguientes, que el extranjero ha dejado de pertenecer a su \u00a0jerarqu\u00eda. \u00a0 \u00a0<\/p>\n<p>2. Multas de cinco (5) hasta doce (12) veces el salario m\u00ednimo \u00a0legal mensual vigente, por cada extranjero, a la persona natural o jur\u00eddica que \u00a0propicie o favorezca su permanencia irregular. \u00a0 \u00a0<\/p>\n<p>3. Multas de uno (1) hasta doce (12) veces el salario m\u00ednimo legal \u00a0mensual vigente, a la persona jur\u00eddica, natural o entidad p\u00fablica que contrate \u00a0o d\u00e9 empleo al extranjero sin el cumplimiento de los requisitos legales, o que \u00a0no d\u00e9 aviso al Departamento Administrativo de Seguridad-DAS\u2011, \u00a0de la vinculaci\u00f3n o desvinculaci\u00f3n dentro de los sesenta (60) d\u00edas calendario \u00a0siguientes. \u00a0 \u00a0<\/p>\n<p>4. Multas de dos (2) hasta seis (6) veces el salario m\u00ednimo legal \u00a0mensual vigente, por cada pasajero, a las empresas de transporte a\u00e9reo, terrestre, \u00a0mar\u00edtimo o fluvial, o a las agencias propietarias o consignatarias que incurran \u00a0en las siguientes faltas: \u00a0 \u00a0<\/p>\n<p>a) Transportar extranjeros sin la documentaci\u00f3n legal \u00a0correspondiente, sin perjuicio de la obligaci\u00f3n de la empresa de devolverlos \u00a0por su cuenta, cuando las autoridades de migraci\u00f3n no autoricen el ingreso; \u00a0 \u00a0<\/p>\n<p>b) No poner a disposici\u00f3n de las autoridades de migraci\u00f3n a su \u00a0arribo al pa\u00eds, a la persona que ha sido deportada, expulsada, o devuelta, u \u00a0omitir o retardar la entrega de la documentaci\u00f3n correspondiente; \u00a0 \u00a0<\/p>\n<p>c) No presentar la lista de pasajeros y tripulantes en la \u00a0oportunidad y con la informaci\u00f3n solicitada por la autoridad migratoria; \u00a0 \u00a0<\/p>\n<p>d) Incumplimiento de las dem\u00e1s obligaciones contenidas en el \u00a0Cap\u00edtulo IV del T\u00edtulo VII del \u00a0presente decreto. \u00a0 \u00a0<\/p>\n<p>5 Multas de cinco (5) hasta quince (15) veces el salario m\u00ednimo \u00a0legal mensual \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 vigente, sin \u00a0perjuicio de las dem\u00e1s sanciones legales, a la empresa de transporte \u00a0 a\u00e9reo, terrestre, mar\u00edtimo, fluvial, o a la \u00a0agencia propietaria o consignataria o de turismo, que propicie el ingreso o la \u00a0salida irregular de extranjeros o nacionales del territorio nacional. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 138. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para la graduaci\u00f3n de las multas se tendr\u00e1 en cuenta la gravedad de \u00a0la falta, la reincidencia o la renuencia del infractor. \u00a0 \u00a0<\/p>\n<p>Cuando se presente caso fortuito o fuerza mayor a cuando el extranjero \u00a0se encuentre en estado de indigencia, debidamente comprobados, podr\u00e1 exonerarse \u00a0al infractor, mediante resoluci\u00f3n motivada, de la respectiva sanci\u00f3n, \u00a0conmin\u00e1ndolo mediante amonestaci\u00f3n escrita. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 139. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Cuando una persona natural o jur\u00eddica, nacional o extranjera, o \u00a0entidad p\u00fablica se negare a cancelar la multa impuesta mediante providencia en \u00a0firme, proceder\u00e1 su ejecuci\u00f3n coactiva de conformidad con la ley. \u00a0 \u00a0<\/p>\n<p>CAPITULO II \u00a0 \u00a0<\/p>\n<p>De la deportaci\u00f3n \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 140. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Director del Departamento Administrativo de Seguridad-DAS\u2011, o sus delegados, mediante Resoluci\u00f3n motivada \u00a0podr\u00e1n ordenar la deportaci\u00f3n del extranjero que est\u00e1 incurso en cualquiera de \u00a0las causales establecidas en el art\u00edculo siguiente del presente Decreto. Contra \u00a0dicho acto administrativo proceden los recursos de la v\u00eda gubernativa que se \u00a0conceder\u00e1n en el efecto suspensivo. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Contra la Resoluci\u00f3n que ordena la deportaci\u00f3n como \u00a0consecuencia de la cancelaci\u00f3n de visa por parte del Ministerio de Relaciones \u00a0Exteriores, no proceder\u00e1 recurso alguno, en concordancia con lo dispuesto en el \u00a0Par\u00e1grafo tercero del art\u00edculo 13 del presente Decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 141. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Sin perjuicio de las sanciones legales a que hubiere lugar, ser\u00e1 \u00a0deportado del territorio nacional, el extranjero que incurra en alguna de las \u00a0siguientes causales: \u00a0 \u00a0<\/p>\n<p>1. Haber ingresado o salido del pa\u00eds sin el cumplimiento de las \u00a0normas, que reglamentan su ingreso y salida, siempre y cuando no existan \u00a0circunstancias especiales que ameriten la sanci\u00f3n de multa. \u00a0 \u00a0<\/p>\n<p>2. Haber sido multado por el Departamento Administrativo de \u00a0Seguridad-DAS\u2011, y ser renuente a la \u00a0cancelaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>3. Encontrarse en permanencia irregular en los t\u00e9rminos de este Decreto, \u00a0siempre y cuando no existan circunstancias especiales que ameriten la sanci\u00f3n \u00a0de multa. \u00a0 \u00a0<\/p>\n<p>4. Obtener visa mediante fraude o simulaci\u00f3n, formular declaraci\u00f3n \u00a0falsa en la solicitud de visa o presentar documentos que induzcan a error al \u00a0Ministerio de Relaciones Exteriores o a la autoridad migratoria para su \u00a0ingreso, salida, legalizaci\u00f3n, control y registro. \u00a0 \u00a0<\/p>\n<p>5. No cambiar la visa o no solicitar la visa cuando estuviere en la \u00a0obligaci\u00f3n de hacerlo, o desarrollar una actividad para la cual no est\u00e9 autorizado \u00a0en el correspondiente permiso de ingreso. \u00a0 \u00a0<\/p>\n<p>6. Incurrir en alguna de las causales de que tratan los numerales \u00a03, 4, 6, 7, 8 o 10 del art\u00edculo 113 del presente decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 142. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero que haya sido deportado s\u00f3lo podr\u00e1 ingresar al \u00a0territorio nacional una vez transcurrido el t\u00e9rmino que establezca la \u00a0resoluci\u00f3n respectiva, que no debe ser inferior a seis (6) meses, ni superior a \u00a0cuatro (4) a\u00f1os. \u00a0 \u00a0<\/p>\n<p>CAPITULO III \u00a0 \u00a0<\/p>\n<p>De la expulsi\u00f3n \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 143. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Director del Departamento Administrativo de Seguridad, DAS, o \u00a0sus delegados, sin perjuicio de las sanciones a que hubiere lugar, podr\u00e1 \u00a0ordenar mediante resoluci\u00f3n motivada la expulsi\u00f3n del territorio nacional, del \u00a0extranjero que est\u00e9 incurso en cualquiera de las causales mencionadas a \u00a0continuaci\u00f3n: \u00a0 \u00a0<\/p>\n<p>1. Intervenir o realizar actos que atenten contra la existencia y \u00a0seguridad del Estado o que perturben el orden p\u00fablico. \u00a0 \u00a0<\/p>\n<p>2. Haber incurrido en conductas que, a juicio de la autoridad \u00a0migratoria, califican al extranjero como peligroso para la seguridad o el orden \u00a0p\u00fablico, o la tranquilidad social. \u00a0 \u00a0<\/p>\n<p>3. Dedicarse al comercio o tr\u00e1fico il\u00edcito de estupefacientes, al \u00a0proxenetismo y, en general, revelar conducta antisocial. \u00a0 \u00a0<\/p>\n<p>4. Comerciar il\u00edcitamente con armas o elementos de uso privativo de \u00a0las Fuerzas Armadas. \u00a0 \u00a0<\/p>\n<p>5. Participar directa o indirectamente en el tr\u00e1fico ilegal de \u00a0personas o de sus \u00f3rganos. \u00a0 \u00a0<\/p>\n<p>6. Incumplir una resoluci\u00f3n de deportaci\u00f3n o regresar al pa\u00eds antes \u00a0del t\u00e9rmino de prohibici\u00f3n establecido en la misma. \u00a0 \u00a0<\/p>\n<p>7. Haber sido condenado por delitos comunes en territorio \u00a0extranjero. \u00a0 \u00a0<\/p>\n<p>8. Propiciar el ingreso de extranjeros con falsas promesas de \u00a0contrato, suministro de visa o documentos de entrada o permanencia. \u00a0 \u00a0<\/p>\n<p>9. Tener orden de captura expedida por autoridad extranjera \u00a0comunicada por la Interpol. \u00a0 \u00a0<\/p>\n<p>10. Adicionado por el Decreto 1384 de 2002, \u00a0art\u00edculo 3. Haber sido dictada en su contra sentencia condenatoria \u00a0debidamente ejecutoriada, en que no contemple como accesoria la pena de \u00a0expulsi\u00f3n del territorio nacional. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Contra el acto administrativo que imponga la medida de \u00a0expulsi\u00f3n, proceder\u00e1n los recursos de la v\u00eda gubernativa, que se conceder\u00e1n en \u00a0el efecto suspensivo, a menos que razones imperiosas de seguridad nacional se \u00a0opongan a ello. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 144. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Cuando la expulsi\u00f3n se decrete como pena accesoria mediante \u00a0sentencia ejecutoriada, el Director del Departamento Administrativo de \u00a0Seguridad, DAS, o sus delegados, mediante auto, dar\u00e1n cumplimiento a la \u00a0expulsi\u00f3n del extranjero y har\u00e1n las comunicaciones respectivas al Ministerio \u00a0de Relaciones Exteriores y al despacho judicial que dict\u00f3 la medida. \u00a0 \u00a0<\/p>\n<p>Contra este acto administrativo no procede recurso alguno. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 145. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero afectado con una medida de expulsi\u00f3n s\u00f3lo podr\u00e1 \u00a0regresar al pa\u00eds con visa autorizada por el Ministerio de Relaciones \u00a0Exteriores, transcurrido un t\u00e9rmino no menor de cinco (5) a\u00f1os, el cual ser\u00e1 \u00a0se\u00f1alado en el acto administrativo que la ordene o ejecute. \u00a0 \u00a0<\/p>\n<p>CAPITULO IV \u00a0 \u00a0<\/p>\n<p>Medidas comunes al \u00a0t\u00edtulo de sanciones \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 146. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La deportaci\u00f3n y expulsi\u00f3n se comunicar\u00e1 a las Direcciones \u00a0Seccionales del Departamento Administrativo de Seguridad, DAS. Copia del acto \u00a0administrativo se enviar\u00e1 al Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine del Ministerio de Relaciones Exteriores para la \u00a0cancelaci\u00f3n de la visa y registro en sus archivos. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 147. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero que sea objeto de un tr\u00e1mite de deportaci\u00f3n o \u00a0expulsi\u00f3n podr\u00e1 ser retenido preventivamente o sometido a vigilancia por las \u00a0autoridades migratorias. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 148. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero que habiendo sido deportado o expulsado no abandonare \u00a0el territorio nacional dentro de los treinta (30) d\u00edas calendario siguientes a \u00a0la ejecutoria del acto administrativo, podr\u00e1 \u00a0ser arrestado hasta por treinta (30) d\u00edas de conformidad con el art\u00edculo 18 del Decreto 522 de 1971 \u00a0y se regular\u00e1 de conformidad con el procedimiento \u00a0establecido por el C\u00f3digo Nacional de Polic\u00eda. (Nota: El aparte se\u00f1alado en negrilla fue \u00a0declarado nulo por el Consejo de Estado en la Sentencia del 30 de abril de \u00a02009. Exp. \u00a07516. Secci\u00f3n 1\u00aa. Actor: Mauricio Alarc\u00f3n. Ponente: Mar\u00eda Claudia Rojas \u00a0Lasso.). \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 149. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La no comparecencia del extranjero no impedir\u00e1 el tr\u00e1mite normal de \u00a0las diligencias de deportaci\u00f3n y de expulsi\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 150. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Las autoridades migratorias colombianas podr\u00e1n poner a disposici\u00f3n \u00a0de las autoridades del pa\u00eds de origen, del \u00faltimo domicilio, del de su nacionalidad, \u00a0o del pa\u00eds que lo acoja, al extranjero afectado por la inadmisi\u00f3n, \u00a0la deportaci\u00f3n o la expulsi\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 151. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La deportaci\u00f3n o expulsi\u00f3n \u00a0produce la cancelaci\u00f3n de la visa correspondiente. Contra el auto de \u00a0cancelaci\u00f3n de visa no procede recurso alguno. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. El tr\u00e1mite de imposici\u00f3n de sanciones de que trata el \u00a0T\u00edtulo VII del presente decreto se adelantar\u00e1 con \u00a0observancia de las disposiciones del C\u00f3digo Contencioso Administrativo, Parte \u00a0Primera, Libro Primero, en particular por lo dispuesto en su cap\u00edtulo VII \u201cDe las actuaciones administrativas iniciadas de oficio\u201d \u00a0y por las dem\u00e1s normas concordantes. \u00a0 \u00a0<\/p>\n<p>TITULO IX \u00a0 \u00a0<\/p>\n<p>DISPOSICIONES FINALES \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 152. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El titular de visa temporal c\u00f3nyuge o compa\u00f1ero(a) de nacional \u00a0colombiano; padre o madre de nacional colombiano, refugiado o asilado, y \u00a0residente, podr\u00e1 efectuar el cambio de empleador, entidad u ocupaci\u00f3n, sin \u00a0necesidad de la expedici\u00f3n de nueva visa, siempre y cuando se encuentre vigente \u00a0la visa de la cual es titular y la misma se har\u00e1 por el proceso de traspaso. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 153. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero deber\u00e1 ejercer la profesi\u00f3n, oficio, actividad u \u00a0ocupaci\u00f3n indicada en la visa. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. Para ejercer la profesi\u00f3n o actividad autorizada en \u00a0la visa el extranjero deber\u00e1 cumplir con los mismos requisitos consagrados en \u00a0las normas vigentes para los nacionales colombianos, y aportar los documentos \u00a0que le permitan el ejercicio de la profesi\u00f3n respectiva. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. Para aquellas profesiones u oficios no regulados, que \u00a0el extranjero pretenda desarrollar en Colombia, deber\u00e1 acreditar experiencia o \u00a0idoneidad. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 3\u00b0. El extranjero no podr\u00e1 ejercer dentro del territorio \u00a0nacional, m\u00e1s de una profesi\u00f3n, oficio u ocupaci\u00f3n debidamente autorizada en la \u00a0visa, salvo cuando se trate de la docencia universitaria hasta por ocho (8) \u00a0horas semanales, previa comprobaci\u00f3n de la idoneidad acad\u00e9mica. Esta salvedad \u00a0es extensiva a los titulares de Visa Temporal Estudiante que est\u00e9n adelantando \u00a0cursos de postgrado en concordancia con lo dispuesto en el Par\u00e1grafo Segundo \u00a0del art\u00edculo 65 de este decreto. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 4\u00b0. El solicitante de cambio de ocupaci\u00f3n, entidad o \u00a0empleador de que trata el art\u00edculo anterior adem\u00e1s de los requisitos indicados en \u00a0el art\u00edculo 22 del presente decreto deber\u00e1 presentar: \u00a0 \u00a0<\/p>\n<p>1. Carta de solicitud motivada en la que se justifique el cambio de \u00a0empleador, entidad y ocupaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>2. Copia del nuevo contrato o de su modificaci\u00f3n o del acto \u00a0administrativo o del documento con el cual se justifique el cambio de entidad, \u00a0empleador u ocupaci\u00f3n, seg\u00fan el caso. \u00a0 \u00a0<\/p>\n<p>3. Fotocopia de la c\u00e9dula de extranjer\u00eda. \u00a0 \u00a0<\/p>\n<p>4. Cuando el cambio de empleador, entidad u ocupaci\u00f3n implique \u00a0ejercer alguna profesi\u00f3n, el extranjero deber\u00e1 aportar fotocopia autentica del \u00a0titulo profesional, debidamente homologado o convalidado ante el ICFES, matr\u00edcula o tarjeta profesional o experiencia, \u00a0certificado de proporcionalidad expedido por el Ministerio de Trabajo cuando se \u00a0requiera, o permiso provisional o licencia para ejercer en Colombia la \u00a0profesi\u00f3n o actividad respectiva, otorgada por la entidad competente. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 154. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. En concordancia con lo estipulado en el art\u00edculo 152, el extranjero \u00a0que previa autorizaci\u00f3n del Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine, cambie de empleador, entidad u ocupaci\u00f3n \u00a0deber\u00e1 informarlo al Departamento Administrativo de Seguridad, DAS, dentro de \u00a0los sesenta (60) d\u00edas calendario siguientes a la ocurrencia del hecho. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 155. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero podr\u00e1 solicitar ante el Grupo Interno de Trabajo que \u00a0el Ministro de Relaciones Exteriores determine o ante las Oficinas Consulares \u00a0previa autorizaci\u00f3n de aquel, el traspaso de la visa por deterioro, cambio o \u00a0p\u00e9rdida del pasaporte, cuando se requiera alguna aclaraci\u00f3n o cambio de \u00a0entidad, empleador u ocupaci\u00f3n seg\u00fan lo dispuesto en el art\u00edculo 152, con el \u00a0lleno de los siguientes requisitos: \u00a0 \u00a0<\/p>\n<p>1. Diligenciar el formulario \u00a0de solicitud. \u00a0 \u00a0<\/p>\n<p>2. Original y fotocopia de las p\u00e1ginas utilizadas del nuevo \u00a0pasaporte. \u00a0 \u00a0<\/p>\n<p>3. Original y fotocopia de la c\u00e9dula de extranjer\u00eda. \u00a0 \u00a0<\/p>\n<p>4. Original y fotocopia del pasaporte en donde conste la visa que \u00a0se desea traspasar, salvo cuando se trate de p\u00e9rdida del mismo, en cuyo caso \u00a0deber\u00e1 manifestarlo por escrito. \u00a0 \u00a0<\/p>\n<p>5. Certificado de movimiento migratorio expedido por el \u00a0Departamento Administrativo de Seguridad, DAS, con una antelaci\u00f3n no mayor a 30 \u00a0d\u00edas, el cual podr\u00e1 ser suplido mediante la presentaci\u00f3n de los pasaportes en \u00a0donde conste el movimiento migratorio. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 156. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero que hubiere obtenido visa deber\u00e1 observar las \u00a0limitaciones impuestas por la legislaci\u00f3n nacional para establecerse en \u00a0determinadas zonas del territorio nacional. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 157. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Fondo Rotatorio del Ministerio de Relaciones Exteriores se\u00f1alar\u00e1 \u00a0el valor de los derechos que se causar\u00e1n en raz\u00f3n de la expedici\u00f3n o traspaso \u00a0de las visas previstas en el presente decreto. \u00a0 \u00a0<\/p>\n<p>El Departamento Administrativo de Seguridad, DAS, establecer\u00e1 el \u00a0valor de los derechos que se causen por concepto de expedici\u00f3n de documentos, \u00a0de conformidad con lo establecido en las normas vigentes, a favor del Fondo \u00a0Rotatorio de dicho Departamento Administrativo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 158. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Para el debido control, la Direcci\u00f3n del Protocolo, el Grupo \u00a0Interno de Trabajo que el Ministro de Relaciones Exteriores determine, las \u00a0Misiones Diplom\u00e1ticas y las Oficinas Consulares de la Rep\u00fablica deber\u00e1n rendir \u00a0informes sobre las visas otorgadas, a las diferentes dependencias del \u00a0Ministerio de Relaciones Exteriores de acuerdo con las instrucciones que se \u00a0impartan. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Las Misiones Diplom\u00e1ticas y las Oficinas Consulares \u00a0deber\u00e1n enviar, de acuerdo con la clase y categor\u00eda de visas, el informe sobre \u00a0la expedici\u00f3n de visas y los documentos soportes de las mismas a la Direcci\u00f3n \u00a0del Protocolo o al Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine, dentro de los diez primeros d\u00edas de cada mes. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 159. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Ministerio de Relaciones Exteriores intercambiar\u00e1 peri\u00f3dicamente \u00a0informaci\u00f3n con el Departamento Administrativo de Seguridad, DAS, sobre las \u00a0visas expedidas dentro y fuera del territorio nacional, para lo cual podr\u00e1n \u00a0suscribir acuerdos interinstitucionales de cooperaci\u00f3n entre las dos entidades. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. El Ministerio de \u00a0Relaciones Exteriores podr\u00e1 celebrar acuerdos o convenios interadministrativos \u00a0de colaboraci\u00f3n con cualquier entidad oficial tendientes al intercambio \u00a0efectivo de informaci\u00f3n en forma de Mensaje de Datos, que contribuyan a \u00a0soportar las decisiones para el otorgamiento, negaci\u00f3n o cancelaci\u00f3n de visas. \u00a0 \u00a0<\/p>\n<p>El Departamento Administrativo de Seguridad, DAS, podr\u00e1 celebrar \u00a0acuerdos o convenios interadministrativos de que \u00a0trata este art\u00edculo, para soportar las decisiones en el otorgamiento o negaci\u00f3n \u00a0del permiso de ingreso y permanencia, el control migratorio y sanciones, de que \u00a0trata el presente decreto. Igualmente podr\u00e1 celebrar acuerdos o convenios con \u00a0personas jur\u00eddicas de derecho p\u00fablico o privado, que permita el recaudo \u00a0estricto de las multas en d\u00edas no h\u00e1biles, dominicales o festivos, en los \u00a0aeropuertos o puertos del pa\u00eds, para lo cual se tomar\u00e1n las medidas \u00a0pertinentes. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 160. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. En ejercicio del control migratorio y sin perjuicio de lo \u00a0establecido en otras disposiciones legales vigentes, corresponde al Departamento \u00a0Administrativo de Seguridad, DAS, adelantar las investigaciones que considere \u00a0necesarias, de oficio o a solicitud del Grupo Interno de Trabajo que el \u00a0Ministro de Relaciones Exteriores determine, en relaci\u00f3n con el ingreso y \u00a0permanencia de los extranjeros en el pa\u00eds, as\u00ed como con las visas que ellos \u00a0portan, su ocupaci\u00f3n, profesi\u00f3n, oficio o actividad que adelantan en el \u00a0territorio nacional, autenticidad de documentos, verificaci\u00f3n de parentesco, \u00a0verificaci\u00f3n de la convivencia marital, entre otros aspectos. \u00a0 \u00a0<\/p>\n<p>Del resultado de las investigaciones se rendir\u00e1 informe y se \u00a0enviar\u00e1 fotocopia del expediente respectivo al Grupo Interno de Trabajo que el \u00a0Ministro de Relaciones Exteriores determine, para su estudio y decisi\u00f3n \u00a0correspondiente. \u00a0 \u00a0<\/p>\n<p>Si del resultado de la investigaci\u00f3n se deduce la presunta \u00a0existencia de delitos o contravenciones, el Departamento Administrativo de \u00a0Seguridad, DAS, pondr\u00e1 en conocimiento de la autoridad competente lo que \u00a0corresponda. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 161. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Las visas expedidas al amparo \u00a0de los decretos anteriores, mantendr\u00e1n su vigencia; en los dem\u00e1s aspectos se regular\u00e1n \u00a0por las disposiciones del presente decreto. Las denominaciones de las visas \u00a0expedidas con base en los decretos anteriores se adecuar\u00e1n a las nuevas clases \u00a0y categor\u00edas establecidas en el presente decreto, y ser\u00e1n consideradas como un \u00a0traspaso cuando corresponda. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 162. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine, podr\u00e1 contemplar el mecanismo de solicitud de visa por \u00a0correo certificado, para lo cual establecer\u00e1 el procedimiento. En todo caso, la \u00a0entrega de la visa respectiva se efectuar\u00e1 en forma personal \u00fanicamente al \u00a0titular o al funcionario que la entidad o empresa donde presta sus servicios, \u00a0est\u00e1 vinculado o lo patrocina, lo autorice, su representante legal o familiar \u00a0directo. \u00a0 \u00a0<\/p>\n<p>De igual manera, podr\u00e1 realizar brigadas especiales para \u00a0identificar los principales asentamientos de extranjeros en el pa\u00eds, en \u00a0diversas ciudades del pa\u00eds, cuando lo estime conveniente. \u00a0 \u00a0<\/p>\n<p>TITULO X \u00a0 \u00a0<\/p>\n<p>REGULARIZACION DE \u00a0EXTRANJEROS \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 163. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero que hubiese ingresado al pa\u00eds con anterioridad al \u00a0treinta y uno (31) de diciembre de 2000 y se encuentre en permanencia irregular \u00a0a la fecha de publicaci\u00f3n del presente Decreto, podr\u00e1 regularizar su situaci\u00f3n \u00a0migratoria en los t\u00e9rminos y condiciones que se establecen en este T\u00edtulo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 164. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero deber\u00e1 presentar personalmente la solicitud por \u00a0escrito ante la oficina del Departamento Administrativo de Seguridad, DAS, del \u00a0lugar de su residencia, o de aquella que se encuentre m\u00e1s cercana, dentro de \u00a0los ciento veinte (120) d\u00edas calendario siguientes a la fecha de publicaci\u00f3n \u00a0del presente decreto, y anexar\u00e1 los siguientes documentos: \u00a0 \u00a0<\/p>\n<p>1. Original y fotocopia de las p\u00e1ginas usadas de su pasaporte o \u00a0documento de Viaje vigente. \u00a0 \u00a0<\/p>\n<p>2. Prueba de su permanencia en el pa\u00eds con anterioridad al treinta \u00a0y uno (31) de diciembre de 2000. \u00a0 \u00a0<\/p>\n<p>3. Prueba de su actividad o ingresos. \u00a0 \u00a0<\/p>\n<p>4. Referencias sobre su conducta social. \u00a0 \u00a0<\/p>\n<p>5. Tres (3) fotograf\u00edas a color tama\u00f1o 3 x 4. \u00a0 \u00a0<\/p>\n<p>6. los dem\u00e1s documentos que el extranjero considere de importancia \u00a0para el tr\u00e1mite, tales como prueba de parentesco o de convivencia con nacional \u00a0colombiano, certificados de estudios, t\u00edtulos de propiedad de inmuebles, entre \u00a0otros. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. El DAS verificar\u00e1 en sus archivos y en los de la Interpol, los antecedentes existentes sobre el extranjero \u00a0que presente solicitud de regularizaci\u00f3n. El DAS oficiosamente adelantar\u00e1 las \u00a0averiguaciones que considere pertinentes. Ver Decreto 367 de 2002, \u00a0art\u00edculo 1 \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 165. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Recibida la documentaci\u00f3n, el Departamento Admin \u00a0istrativo de Seguridad, DAS, radicar\u00e1 el expediente, \u00a0elaborar\u00e1 un registro del extranjero, le tomar\u00e1 una declaraci\u00f3n sobre su \u00a0permanencia en el pa\u00eds, motivos por los que desea la regularizaci\u00f3n, y los \u00a0dem\u00e1s hechos que contribuyan al esclarecimiento de sus circunstancias \u00a0personales y sociales, le expedir\u00e1 constancia gratuitamente sobre el hecho de \u00a0que se encuentra en proceso de regularizaci\u00f3n, la cual tendr\u00e1 validez por \u00a0sesenta (60) d\u00edas, prorrogable hasta por otros treinta d\u00edas calendario, \u00a0mientras se decide si procede o no su regularizaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 166. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El Departamento Administrativo de Seguridad, DAS, estudiar\u00e1 la \u00a0documentaci\u00f3n y si de la investigaci\u00f3n que se adelante se deduce que se cumplen \u00a0los requisitos establecidos en el presente t\u00edtulo, y previo informe, le \u00a0expedir\u00e1 al extranjero un salvoconducto para tr\u00e1mite de visa, por el t\u00e9rmino de \u00a0180 d\u00edas calendario, improrrogable, sin costo alguno, que lo habilitar\u00e1 para \u00a0permanecer en el territorio nacional, con los mismos derechos y obligaciones de \u00a0un nacional colombiano, conforme a la Constituci\u00f3n y la ley. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 167. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Una vez expedido el salvoconducto para tr\u00e1mite de visa, el \u00a0Departamento Administrativo de Seguridad, DAS, remitir\u00e1 fotocopia del informe \u00a0al Grupo Interno de Trabajo que el Ministro de Relaciones Exteriores determine, \u00a0para que obre como antecedente de la regularizaci\u00f3n del extranjero. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 168. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero que obtenga el salvoconducto contemplado en el \u00a0art\u00edculo 166 de este decreto, durante su vigencia, podr\u00e1 solicitar en el pa\u00eds \u00a0expedici\u00f3n de visa, en una de las clases o categor\u00edas establecidas en el \u00a0art\u00edculo 28, previo el lleno de los requisitos contemplados en el presente \u00a0decreto, para cada una de ellas. \u00a0 \u00a0<\/p>\n<p>La solicitud de visa deber\u00e1 ser tramitada directamente por el \u00a0extranjero, o por la entidad o empresa donde presta sus servicios, est\u00e1 \u00a0vinculado o lo patrocina, o por su representante legal, ante el Grupo Interno \u00a0de Trabajo que el Ministro de Relaciones Exteriores determine. As\u00ed mismo el \u00a0extranjero puede remitir la solicitud con la documentaci\u00f3n correspondiente por \u00a0correo certificado al Grupo Interno de Trabajo que el Ministro de Relaciones \u00a0Exteriores determine. En todo caso, el formulario deber\u00e1 estar firmado por el \u00a0interesado y la entrega de la visa respectiva se efectuar\u00e1 en forma personal \u00a0\u00fanicamente a su titular. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. El valor de la visa que se expida al extranjero \u00a0regularizado, en todos los casos, ser\u00e1 el establecido por el Fondo Rotatorio \u00a0del Ministerio de Relaciones Exteriores, de acuerdo con la clase o categor\u00eda y \u00a0lo que corresponda por impuesto de timbre. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. El Ministerio de Relaciones Exteriores, tomar\u00e1 las \u00a0medidas que considere pertinentes, para la expedici\u00f3n de la visa que \u00a0corresponda, al extranjero favorecido con la regularizaci\u00f3n y para tal fin \u00a0podr\u00e1 comisionar a funcionarios del Grupo Interno de Trabajo que el Ministro de \u00a0Relaciones Exteriores determine para que se trasladen a otras ciudades del \u00a0pa\u00eds, con el fin de agilizar el proceso de regularizaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 169. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. No proceder\u00e1 la regularizaci\u00f3n del extranjero: \u00a0 \u00a0<\/p>\n<p>1. Que haya sido condenado o que est\u00e9 siendo procesado y se hubiese \u00a0proferido en su contra resoluci\u00f3n de acusaci\u00f3n, en ambos casos por delito que \u00a0contemple pena privativa de la libertad de dos o m\u00e1s a\u00f1os. \u00a0 \u00a0<\/p>\n<p>2. Que haya incumplido una orden de expulsi\u00f3n del pa\u00eds. \u00a0 \u00a0<\/p>\n<p>3. Que a juicio de las autoridades migratorias represente peligro \u00a0para la seguridad ciudadana o el orden p\u00fablico. \u00a0 \u00a0<\/p>\n<p>4. Que est\u00e9 solicitado por autoridad judicial o de polic\u00eda de otro \u00a0pa\u00eds, para lo cual el DAS verificar\u00e1 con Interpol. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 170. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. La falsedad de cualquiera de los documentos o de las declaraciones, \u00a0que obren para los efectos del presente t\u00edtulo, ser\u00e1 causal de cancelaci\u00f3n del \u00a0salvoconducto o de la visa que se le conceda y se proceder\u00e1 a la deportaci\u00f3n \u00a0del extranjero. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 171. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Contra la decisi\u00f3n que niegue el salvoconducto para tr\u00e1mite de \u00a0visa, proceder\u00e1n los recursos de la v\u00eda gubernativa. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 172. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El extranjero que, dentro del plazo se\u00f1alado en el art\u00edculo 164 del \u00a0presente decreto no se acoja al plan de regularizaci\u00f3n o que habi\u00e9ndose acogido \u00a0no cumpla con los requisitos exigidos para tal fin o que le sea negado el \u00a0salvoconducto de que trata el art\u00edculo 166 del presente decreto, o que por \u00a0alguna circunstancia se le niegue la visa, deber\u00e1 salir del territorio nacional \u00a0dentro de los 90 d\u00edas calendario siguientes a la ocurrencia del hecho, so pena \u00a0de ser deportado. \u00a0 \u00a0<\/p>\n<p>En este \u00faltimo caso el Departamento Administrativo de Seguridad, \u00a0DAS, expedir\u00e1 al extranjero un salvoconducto por dicho t\u00e9rmino para salir del \u00a0pa\u00eds. \u00a0 \u00a0<\/p>\n<p>TITULO XI \u00a0 \u00a0<\/p>\n<p>VIGENCIA \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 173. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Las disposiciones generales del Cap\u00edtulo I, T\u00edtulo II, salvo los art\u00edculos 9\u00b0, 16, 17 y 22 del presente \u00a0decreto, empezar\u00e1n a regir a partir de la fecha d e su publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 174. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Las normas contenidas en el T\u00edtulo X del presente decreto regir\u00e1n \u00a0treinta (30) d\u00edas calendario despu\u00e9s de la fecha de su publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 175. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. Los art\u00edculos 9\u00b0, 13, 16, 17, 22 y 23 del Cap\u00edtulo I del T\u00edtulo II y dem\u00e1s normas del presente decreto, salvo lo dispuesto \u00a0en los art\u00edculos 173 y 174 regir\u00e1n dos (2) meses despu\u00e9s de la fecha de su \u00a0publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 176. Derogado por el Decreto 4000 de 2004, \u00a0art\u00edculo 125. El presente decreto deroga los Decretos 2371 del 27 de diciembre de 1996 y 2073 de 1999 y dem\u00e1s disposiciones \u00a0que le sean contrarias. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a \u00a08 de octubre de 2001. \u00a0 \u00a0<\/p>\n<p>ANDRES PASTRANA ARANGO \u00a0 \u00a0<\/p>\n<p>El Ministro de Relaciones \u00a0Exteriores, \u00a0 \u00a0<\/p>\n<p>Guillermo Fern\u00e1ndez de Soto. \u00a0 \u00a0<\/p>\n<p>El Director del \u00a0Departamento Administrativo de Seguridad, DAS, \u00a0 \u00a0<\/p>\n<p>Germ\u00e1n Gustavo Jaramillo Piedrah\u00edta. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 2107 DE 2001 \u00a0 \u00a0 (octubre 8) \u00a0 \u00a0 por el cual se dictan \u00a0disposiciones sobre la expedici\u00f3n de visas, control y regularizaci\u00f3n de \u00a0extranjeros y se dictan otras disposiciones en materia de inmigraci\u00f3n. \u00a0 \u00a0 Nota 1: Derogado parcialmente por el Decreto 4000 de 2004. \u00a0 \u00a0 Nota 2: \u00a0Modificado por el Decreto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-30084","post","type-post","status-publish","format-standard","hentry","category-decretos-2001"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/30084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=30084"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/30084\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=30084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=30084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=30084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}