{"id":30363,"date":"2023-07-18T21:50:21","date_gmt":"2023-07-18T21:50:21","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/18\/decreto-2834-de-2001\/"},"modified":"2023-07-18T21:50:21","modified_gmt":"2023-07-18T21:50:21","slug":"decreto-2834-de-2001","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/18\/decreto-2834-de-2001\/","title":{"rendered":"DECRETO 2834 DE 2001"},"content":{"rendered":"\n<p>DECRETO 2834 DE 2001 \u00a0 \u00a0<\/p>\n<p>(diciembre \u00a021) \u00a0 \u00a0<\/p>\n<p>por el cual se promulga el Convenio entre el \u00a0Gobierno de la Rep\u00fablica de Colombia y el Gobierno de la Federaci\u00f3n de Rusia \u00a0sobre Cooperaci\u00f3n Cultural y Cient\u00edfica, firmado en Santa Fe de Bogot\u00e1, a los \u00a0veintis\u00e9is (26) d\u00edas del mes de noviembre de mil novecientos noventa y siete \u00a0(1997). \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, en uso de \u00a0las facultades que le otorga el art\u00edculo 189 numeral 2 de la Constituci\u00f3n \u00a0Pol\u00edtica de Colombia y en cumplimiento de la Ley 7\u00aa de 1944, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que la Ley 7\u00aa \u00a0del 30 de noviembre de 1944, en su art\u00edculo 1\u00b0 dispone que los tratados, \u00a0convenios, convenciones, acuerdos, arreglos u otros actos internacionales aprobados \u00a0por el Congreso, no se considerar\u00e1n vigentes como leyes internas, mientras no \u00a0hayan sido perfeccionados por el Gobierno en su car\u00e1cter de tales, mediante el \u00a0canje de ratificaciones o el dep\u00f3sito de los instrumentos de ratificaci\u00f3n, u \u00a0otra formalidad equivalente; \u00a0 \u00a0<\/p>\n<p>Que la misma ley en su art\u00edculo segundo ordena la \u00a0promulgaci\u00f3n de los tratados y convenios internacionales una vez sea \u00a0perfeccionado el v\u00ednculo internacional que ligue a Colombia; \u00a0 \u00a0<\/p>\n<p>Que el Congreso Nacional, mediante Ley 566 \u00a0del 2 de febrero de 2000, publicada en el Diario Oficial n\u00famero \u00a043.883 del 7 de febrero de 2000, aprob\u00f3 el Convenio entre el Gobierno de la \u00a0Rep\u00fablica de Colombia y el Gobierno de la Federaci\u00f3n de Rusia sobre Cooperaci\u00f3n \u00a0Cultural y Cient\u00edfica, firmado en Santa Fe de Bogot\u00e1 el 26 de noviembre de \u00a01997; \u00a0 \u00a0<\/p>\n<p>Que la Corte Constitucional, en Sentencia C-924\/2000 del 19 de \u00a0julio de 2000, declar\u00f3 exequible la Ley 566 \u00a0del 2 de febrero de 2000 y el Convenio entre el Gobierno de la Rep\u00fablica de \u00a0Colombia y el Gobierno de la Federaci\u00f3n de Rusia sobre Co operaci\u00f3n Cultural y \u00a0Cient\u00edfica, firmado en Santa Fe de Bogot\u00e1, el 26 de noviembre de 1997; \u00a0 \u00a0<\/p>\n<p>Que mediante Nota Verbal n\u00famero 130-N\/UKSV del 30 de \u00a0diciembre de 1997, el Gobierno de la Federaci\u00f3n de Rusia notific\u00f3 el \u00a0cumplimiento de sus tr\u00e1mites internos y, en el mismo sentido, el Gobierno de la \u00a0Rep\u00fablica de Colombia remiti\u00f3 la Nota Diplom\u00e1tica DM.\/OJ.AT. n\u00famero 33011 del \u00a017 de noviembre de 2000. En consecuencia, el citado instrumento internacional \u00a0entr\u00f3 en vigor el 17 de noviembre de 2000, de acuerdo a lo previsto en su \u00a0art\u00edculo 26, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Prom\u00falgase el Convenio entre el \u00a0Gobierno de la Rep\u00fablica de Colombia y el Gobierno de la Federaci\u00f3n de Rusia \u00a0sobre Cooperaci\u00f3n Cultural y Cient\u00edfica, firmado en Santa Fe de Bogot\u00e1, a los \u00a0veintis\u00e9is (26) d\u00edas del mes de noviembre de mil novecientos noventa y siete \u00a0(1997). \u00a0 \u00a0<\/p>\n<p>(Para ser transcrito en este lugar se adjunta \u00a0fotocopia del texto del Convenio entre el Gobierno de la Rep\u00fablica de Colombia \u00a0y el Gobierno de la Federaci\u00f3n de Rusia sobre Cooperaci\u00f3n Cultural y \u00a0Cient\u00edfica, firmado en Santa Fe de Bogot\u00e1, a los veintis\u00e9is (26) d\u00edas del mes \u00a0de noviembre de mil novecientos noventa y siete (1997). \u00a0 \u00a0<\/p>\n<p>\u00abCONVENIO ENTRE EL GOBIERNO DE LA REPUBLICA DE \u00a0COLOMBIA\u00a0<\/p>\n<p>\u00a0 Y EL GOBIERNO DE LA FEDERACION DE RUSIA SOBRE COOPERACION CULTURAL Y CIENTIFICA \u00a0 \u00a0<\/p>\n<p>El Gobierno de la Rep\u00fablica de Colombia y el \u00a0Gobierno de la Federaci\u00f3n de Rusia, en lo sucesivo denominados Las Partes, en \u00a0su aspiraci\u00f3n por fortalecer las relaciones de amistad, por incrementar el \u00a0mutuo entendimiento y la confianza entre los pueblos de ambas naciones y por \u00a0ampliar los v\u00ednculos culturales entre los dos pa\u00edses en el campo de la cultura, \u00a0el arte, la ciencia, la educaci\u00f3n, el cine, los medios de comunicaci\u00f3n, el \u00a0deporte, los intercambios juveniles y el turismo, han convenido lo siguiente: \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0PRIMERO \u00a0 \u00a0<\/p>\n<p>Las \u00a0Partes, de conformidad con las disposiciones del presente Convenio, \u00a0desarrollar\u00e1n la cooperaci\u00f3n multifac\u00e9tica en el campo de la cultura, la \u00a0ciencia y la educaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0SEGUNDO \u00a0 \u00a0<\/p>\n<p>Cada una \u00a0de las Partes har\u00e1 todo lo posible para divulgar los valores art\u00edsticos y \u00a0culturales de la otra Parte, fomentando las respectivas iniciativas estatales, \u00a0p\u00fablicas y privadas. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0TERCERO \u00a0 \u00a0<\/p>\n<p>Las \u00a0Partes promover\u00e1n rec\u00edprocamente el establecimiento de contactos directos en el \u00a0campo de la cultura y prestar\u00e1n ayuda en la realizaci\u00f3n de giras art\u00edsticas, \u00a0tanto de grupos profesionales de \u00f3pera, m\u00fasica, teatro y otros, como de \u00a0solistas. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0CUARTO \u00a0 \u00a0<\/p>\n<p>Las \u00a0Partes se informar\u00e1n oportunamente sobre las conferencias, concursos, festivales \u00a0y otros eventos internacionales en el campo de la cultura y el arte que tengan \u00a0lugar en su pa\u00eds. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0QUINTO \u00a0 \u00a0<\/p>\n<p>Las \u00a0Partes contribuir\u00e1n a la cooperaci\u00f3n entre museos, bibliotecas y archivos \u00a0estatales, tomando las medidas necesarias para la prestaci\u00f3n de las garant\u00edas \u00a0adecuadas durante el traslado y exhibici\u00f3n de los bienes culturales. \u00a0 \u00a0<\/p>\n<p>Las Partes contribuir\u00e1n a la cooperaci\u00f3n directa \u00a0entre las bibliotecas nacionales; sobre todo, en lo que tiene que ver con el \u00a0acceso a material de informaci\u00f3n referente a las tem\u00e1ticas rusa o colombiana. \u00a0 \u00a0<\/p>\n<p>ARTICULO SEXTO \u00a0 \u00a0<\/p>\n<p>Las Partes estimular\u00e1n el desarrollo de contactos \u00a0directos y la cooperaci\u00f3n entre las instituciones culturales, organizaciones \u00a0art\u00edsticas, asociaciones, fondos y otras organizaciones culturale s y educativas \u00a0de ambos pa\u00edses sobre la base de la firma de protocolos, programas y otros \u00a0documentos de trabajo. \u00a0 \u00a0<\/p>\n<p>ARTICULO SEPTIMO \u00a0 \u00a0<\/p>\n<p>Las Partes contribuir\u00e1n al mutuo estudio de la \u00a0experiencia adquirida en el campo de la cultura, el arte y la literatura, \u00a0mediante la organizaci\u00f3n de conferencias, simposios y otros foros cient\u00edficos; \u00a0as\u00ed como por medio del intercambio de especialistas y de la realizaci\u00f3n \u00a0conjunta de actividades cient\u00edficas e investigativas. \u00a0 \u00a0<\/p>\n<p>ARTICULO OCTAVO \u00a0 \u00a0<\/p>\n<p>Las Partes tomar\u00e1n, de acuerdo con las normas del \u00a0derecho internacional y de la legislaci\u00f3n nacional, las medidas \u00a0correspondientes para la prevenci\u00f3n del ingreso, salida y traspaso ilegales de \u00a0los derechos de propiedad sobre los bienes culturales de cada uno de los \u00a0pa\u00edses; asegurar\u00e1n la cooperaci\u00f3n entre los \u00f3rganos estatales competentes de la \u00a0Federaci\u00f3n de Rusia y de la Rep\u00fablica de Colombia en el intercambio de \u00a0informaci\u00f3n y en la toma de medidas relacionadas con el restablecimiento de los \u00a0derechos legales de propiedad sobre los bienes culturales y con la devoluci\u00f3n \u00a0de \u00e9stos \u00faltimos en el caso de que hayan ingresado o hayan sido sustra\u00eddos \u00a0ilegalmente del territorio de ambos Estados. \u00a0 \u00a0<\/p>\n<p>ARTICULO NOVENO \u00a0 \u00a0<\/p>\n<p>Las Partes contribuir\u00e1n a la cooperaci\u00f3n en el campo \u00a0de la cinematograf\u00eda y en la divulgaci\u00f3n del arte cinematogr\u00e1fico de sus pa\u00edses \u00a0mediante el intercambio, comercial o no, de pel\u00edculas. Las Partes estimular\u00e1n \u00a0los encuentros entre personalidades del cine y especialistas en el campo de la \u00a0cinematograf\u00eda. \u00a0 \u00a0<\/p>\n<p>ARTICULO DECIMO \u00a0 \u00a0<\/p>\n<p>Las Partes estimular\u00e1n la cooperaci\u00f3n en el campo de \u00a0los medios de comunicaci\u00f3n, en particular mediante la celebraci\u00f3n de convenios \u00a0directos entre las instituciones y organizaciones profesionales \u00a0correspondientes, la producci\u00f3n conjunta de materiales audiovisuales e \u00a0impresos, el intercambio de especialistas y la organizaci\u00f3n de ferias y \u00a0exposiciones. \u00a0 \u00a0<\/p>\n<p>Las Partes apoyar\u00e1n la cooperaci\u00f3n entre las \u00a0empresas nacionales de radio y televisi\u00f3n rusas y colombianas. Los t\u00e9rminos y \u00a0condiciones de esta cooperaci\u00f3n ser\u00e1n estipuladas en acuerdos directos entre \u00a0las Partes. \u00a0 \u00a0<\/p>\n<p>ARTICULO DECIMO PRIMERO \u00a0 \u00a0<\/p>\n<p>Las Partes estimular\u00e1n la cooperaci\u00f3n en el campo de \u00a0la protecci\u00f3n de los derechos de autor y conexos. La normatividad y condiciones \u00a0de este tipo de cooperaci\u00f3n se fijar\u00e1n en acuerdos especiales entre las Partes. \u00a0 \u00a0<\/p>\n<p>ARTICULO DECIMO SEGUNDO \u00a0 \u00a0<\/p>\n<p>Las Partes prestar\u00e1n ayuda a la creaci\u00f3n y \u00a0funcionamiento de centros culturales y de informaci\u00f3n de ambos pa\u00edses en la \u00a0Federaci\u00f3n de Rusia y en la Rep\u00fablica de Colombia sobre la base de condiciones \u00a0de reciprocidad. \u00a0 \u00a0<\/p>\n<p>ARTICULO DECIMO TERCERO \u00a0 \u00a0<\/p>\n<p>Las Partes contribuir\u00e1n a la cooperaci\u00f3n entre los \u00a0centros de archivo de ambos pa\u00edses mediante el intercambio de especialistas y \u00a0la prestaci\u00f3n de la ayuda t\u00e9cnica para la conservaci\u00f3n de los materiales de \u00a0archivos, incluida la microfilmaci\u00f3n de documentos de archivo. \u00a0 \u00a0<\/p>\n<p>ARTICULO DECIMO CUARTO \u00a0 \u00a0<\/p>\n<p>Las Partes desarrollar\u00e1n la cooperaci\u00f3n en el campo \u00a0de la ciencia sobre la base de convenios directos entre las organizaciones y \u00a0departamentos correspondientes. \u00a0 \u00a0<\/p>\n<p>ARTICULO DECIMO QUINTO \u00a0 \u00a0<\/p>\n<p>Las Partes contribuir\u00e1n al desarrollo de la \u00a0cooperaci\u00f3n de mutuo beneficio entre el Instituto Colombiano para el Desarrollo \u00a0de la Ciencia y la Tecnolog\u00eda Francisco Jos\u00e9 de Caldas, Colciencias y la \u00a0Academia de Ciencias de Rusia. \u00a0 \u00a0<\/p>\n<p>ARTICULO DECIMO SEXTO \u00a0 \u00a0<\/p>\n<p>Las Partes \u00a0contribuir\u00e1n a la cooperaci\u00f3n y al intercambio de experiencias en el campo de \u00a0la educaci\u00f3n, mediante el otorgamiento de becas en \u00e1reas de inter\u00e9s mutuo, \u00a0estimulando el intercambio de especialistas, cient\u00edficos, estudiantes y \u00a0alumnos, el desarrollo de contactos directos entre las instituciones de \u00a0educaci\u00f3n, organizaciones de ciencia, cultura, arte y deporte y la interacci\u00f3n \u00a0en el campo de la preparaci\u00f3n profesional y la capacitaci\u00f3n de personal. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0DECIMO SEPTIMO \u00a0 \u00a0<\/p>\n<p>Las \u00a0Partes estimular\u00e1n la cooperaci\u00f3n para la ense\u00f1anza y la difusi\u00f3n de las \u00a0lenguas de ambos pa\u00edses en el sistema educativo a todos los niveles, incluyendo \u00a0centros de ense\u00f1anza para adultos; en particular, mediante: \u00a0 \u00a0<\/p>\n<p>\u00a0Selecci\u00f3n y env\u00edo de profesores, \u00a0conferencistas y especialistas consultores; \u00a0 \u00a0<\/p>\n<p>\u00a0La puesta a \u00a0disposici\u00f3n de manuales y material did\u00e1ctico y la cooperaci\u00f3n en la elaboraci\u00f3n \u00a0de los manuales; \u00a0 \u00a0<\/p>\n<p>\u00a0La \u00a0participaci\u00f3n de profesores y estudiantes en los cursos de preparaci\u00f3n y \u00a0perfeccionamiento realizados por la otra Parte; \u00a0 \u00a0<\/p>\n<p>\u00a0El intercambio de experiencias en el campo de \u00a0tecnolog\u00eda actuales de ense\u00f1anza de lenguas extranjeras; \u00a0 \u00a0<\/p>\n<p>\u00a0La utilizaci\u00f3n de los medios de radio y \u00a0televisi\u00f3n para la divulgaci\u00f3n de la lengua del otro pa\u00eds; \u00a0 \u00a0<\/p>\n<p>\u00a0La capacitaci\u00f3n de traductores de literatura; \u00a0 \u00a0<\/p>\n<p>\u00a0El \u00a0intercambio de cient\u00edficos, profesores, estudiantes de pregrado y posgrado y \u00a0alumnos en general, con el fin de profundizar su conocimiento de la lengua y \u00a0realizar investigaciones en el campo de la ling\u00fc\u00edstica. \u00a0 \u00a0<\/p>\n<p>ARTICULO DECIMO OCTAVO \u00a0 \u00a0<\/p>\n<p>Las Partes contribuir\u00e1n al reconocimiento rec\u00edproco \u00a0de diplomas, t\u00edtulos y grados de educaci\u00f3n superior. A este respecto se \u00a0llevar\u00e1n a cabo negociaciones con el fin de firmar un convenio en este campo. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0DECIMO NOVENO \u00a0 \u00a0<\/p>\n<p>Las \u00a0Partes estimular\u00e1n la cooperaci\u00f3n entre las organizaciones y asociaciones \u00a0juveniles, as\u00ed como los contactos directos entre los j\u00f3venes de ambos pa\u00edses. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0VIGESIMO \u00a0 \u00a0<\/p>\n<p>Las \u00a0Partes cooperar\u00e1n en el campo de la salud p\u00fablica y la ciencia m\u00e9dica sobre la \u00a0base de convenios directos entre las respectivas organizaciones e instituciones. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0VIGESIMO PRIMERO \u00a0 \u00a0<\/p>\n<p>Las \u00a0Partes contribuir\u00e1n al desarrollo de la cooperaci\u00f3n en el campo del deporte y \u00a0la educaci\u00f3n f\u00edsica y estimular\u00e1n los v\u00ednculos directos entre deportistas, \u00a0entrenadores, organizaciones y equipos deportivos de ambos pa\u00edses. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0VIGESIMO SEGUNDO \u00a0 \u00a0<\/p>\n<p>Las \u00a0Partes contribuir\u00e1n a los intercambios tur\u00edsticos con el fin de conocer \u00a0mutuamente y divulgar la cultura de ambos pa\u00edses. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0VIGESIMO TERCERO \u00a0 \u00a0<\/p>\n<p>Las Partes \u00a0asegurar\u00e1n peri\u00f3dicamente la firma de programas en el campo de la cultura, la \u00a0ciencia y la educaci\u00f3n, en los cuales se estipular\u00e1n las actividades concretas \u00a0y las condiciones, tanto financieras como de otra \u00edndole para su realizaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Con este \u00a0fin ser\u00e1 creada la Comisi\u00f3n Mixta Colombo-Rusa para la cooperaci\u00f3n en el campo \u00a0de la cultura, la ciencia y la educaci\u00f3n, la cual se reunir\u00e1 en las ciudades de \u00a0Bogot\u00e1 y Mosc\u00fa, alternadamente. La coordinac i\u00f3n de las actividades de la \u00a0Comisi\u00f3n Mixta y la firma de los programas de intercambios acordados estar\u00e1n a \u00a0cargo del Ministerio de Relaciones Exteriores de la Rep\u00fablica de Colombia y el \u00a0Ministerio de Relaciones Exteriores de la Federaci\u00f3n de Rusia. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0VIGESIMO CUARTO \u00a0 \u00a0<\/p>\n<p>Las \u00a0controversias sobre la interpretaci\u00f3n o aplicaci\u00f3n del presente convenio se \u00a0resolver\u00e1n mediante el acuerdo mutuo entre las Partes o de conformidad con los \u00a0procedimientos contemplados por el Derecho Internacional para la Soluci\u00f3n \u00a0Pac\u00edfica de Controversias. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0VIGESIMO QUINTO \u00a0 \u00a0<\/p>\n<p>En la fecha \u00a0en la que entre en vigor el presente Convenio, perder\u00e1 vigencia en las \u00a0relaciones entre la Rep\u00fablica de Colombia y la Federaci\u00f3n de Rusia, el Convenio \u00a0sobre Cooperaci\u00f3n Cultural y Cient\u00edfica entre la Rep\u00fablica de Colombia y la \u00a0Uni\u00f3n de Rep\u00fablicas Socialistas Sovi\u00e9ticas, suscrito el 3 de agosto de 1970. La \u00a0terminaci\u00f3n de \u00e9ste, no afectar\u00e1 la ejecuci\u00f3n de los programas y los proyectos \u00a0ya iniciados sobre la base del mismo. \u00a0 \u00a0<\/p>\n<p>ARTICULO \u00a0VIGESIMO SEXTO \u00a0 \u00a0<\/p>\n<p>El \u00a0presente Convenio entrar\u00e1 en vigor en la fecha de la \u00faltima notificaci\u00f3n sobre \u00a0el cumplimiento por cada una de las Partes de los tr\u00e1mites internos necesarios \u00a0para su entrada en vigor. \u00a0 \u00a0<\/p>\n<p>El \u00a0presente Convenio tendr\u00e1 una duraci\u00f3n de cinco (5) a\u00f1os y se prorrogar\u00e1 \u00a0autom\u00e1ticamente por per\u00edodos subsecuentes de cinco (5) a\u00f1os, a menos que una de \u00a0las Partes comunique por escrito a la otra Parte su intenci\u00f3n de darlo por \u00a0terminado con una antelaci\u00f3n no menor de seis (6) meses a la fecha de la \u00a0expiraci\u00f3n del per\u00edodo quinquenal correspondiente. \u00a0 \u00a0<\/p>\n<p>La \u00a0terminaci\u00f3n del presente Convenio no afectar\u00e1 el cumplimiento de los programas \u00a0y los proyectos que se encuentren en ejecuci\u00f3n y que hayan sido puestos en \u00a0marcha sobre la base de \u00e9ste. \u00a0 \u00a0<\/p>\n<p>Firmado \u00a0en la ciudad de Santa Fe de Bogot\u00e1, a los veintis\u00e9is (26) d\u00edas del mes de \u00a0noviembre de mil novecientos noventa y siete (1997), en dos originales, cada \u00a0uno en idiomas espa\u00f1ol y ruso, teniendo ambos textos el mismo valor. \u00a0 \u00a0<\/p>\n<p>Por el \u00a0Gobierno de la Rep\u00fablica de Colombia, \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Mar\u00eda Emma Mej\u00eda V\u00e9lez, \u00a0 \u00a0<\/p>\n<p>Ministra de Relaciones Exteriores. \u00a0 \u00a0<\/p>\n<p>Por el \u00a0Gobierno de la Federaci\u00f3n de Rusia, \u00a0 \u00a0<\/p>\n<p>Evgueni \u00a0Primakov, \u00a0 \u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ministro \u00a0de Relaciones Exteriores.\u00bb \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a02\u00b0. El presente decreto rige a partir de la fecha de su publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese \u00a0y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en \u00a0Bogot\u00e1, D. C., a 21 de diciembre de 2001. \u00a0 \u00a0<\/p>\n<p>ANDRES \u00a0PASTRANA ARANGO \u00a0 \u00a0<\/p>\n<p>El Ministro \u00a0de Relaciones Exteriores, \u00a0 \u00a0<\/p>\n<p>Guillermo \u00a0Fern\u00e1ndez De Soto. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 2834 DE 2001 \u00a0 \u00a0 (diciembre \u00a021) \u00a0 \u00a0 por el cual se promulga el Convenio entre el \u00a0Gobierno de la Rep\u00fablica de Colombia y el Gobierno de la Federaci\u00f3n de Rusia \u00a0sobre Cooperaci\u00f3n Cultural y Cient\u00edfica, firmado en Santa Fe de Bogot\u00e1, a los \u00a0veintis\u00e9is (26) d\u00edas del mes de noviembre de mil [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-30363","post","type-post","status-publish","format-standard","hentry","category-decretos-2001"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/30363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=30363"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/30363\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=30363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=30363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=30363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}