{"id":30417,"date":"2023-07-18T21:47:32","date_gmt":"2023-07-18T21:47:32","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/18\/decreto-363-de-2001\/"},"modified":"2023-07-18T21:47:32","modified_gmt":"2023-07-18T21:47:32","slug":"decreto-363-de-2001","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/18\/decreto-363-de-2001\/","title":{"rendered":"DECRETO 363 DE 2001"},"content":{"rendered":"\n<p>\u00a0\u00a0<\/p>\n<p>DECRETO 363 DE \u00a02001 \u00a0 \u00a0<\/p>\n<p>(marzo 8) \u00a0 \u00a0<\/p>\n<p>por el \u00a0cual se autoriza a unos Magistrados del Consejo Superior de la Judicatura para \u00a0que acepten una invitaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>El Ministro de Justicia y del Derecho de la Rep\u00fablica de \u00a0Colombia, delegatario de funciones presidenciales conforme al Decreto \u00a0313 del 23 de febrero de 2001, en ejercicio de las facultades conferidas \u00a0por los art\u00edculos 129 y 189 numeral 18 de la Constituci\u00f3n \u00a0Pol\u00edtica, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que el Consejo General del Poder Judicial de Espa\u00f1a, ha \u00a0formulado invitaci\u00f3n a los doctores Gilberto Orozco Orozco, Magistrado de la \u00a0Sala Administrativa y Presidente del Consejo Superior de la Judicatura, y \u00a0Carlos Enrique Mar\u00edn V\u00e9lez, Magistrado de la Sala Administrativa del Consejo \u00a0Superior de la Judicatura, para participar en el II Encuentro de Consejos de la \u00a0Judicatura, que se realizar\u00e1 en la ciudad de Barcelona (Espa\u00f1a) del 26 al 28 de \u00a0marzo del a\u00f1o en curso; \u00a0 \u00a0<\/p>\n<p>Que la invitaci\u00f3n comprende el pago de una beca para apoyar \u00a0los gastos de participaci\u00f3n en el evento; \u00a0 \u00a0<\/p>\n<p>Que para la Rama Judicial se hace necesaria la participaci\u00f3n \u00a0de los doctores Gilberto Orozco Orozco, Magistrado de la Sala Administrativa y \u00a0Presidente del Consejo Superior de la Judicatura, y Carlos Enrique Mar\u00edn V\u00e9lez, \u00a0Magistrado de la Sala Administrativa del Consejo Superior de la Judicatura; \u00a0 \u00a0<\/p>\n<p>Que de acuerdo con lo dispuesto por el art\u00edculo 129 de la Constituci\u00f3n Pol\u00edtica, \u00a0\u201clos servidores p\u00fablicos no podr\u00e1n aceptar cargos, honores o recompensas de \u00a0gobiernos extranjeros u organismos internacionales, ni para celebrar contratos \u00a0con ellos, sin previa autorizaci\u00f3n del Gobierno\u201d; \u00a0 \u00a0<\/p>\n<p>Que en m\u00e9rito de lo expuesto, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Autor\u00edzase a los doctores Gilberto Orozco \u00a0Orozco, Magistrado de la Sala Administrativa y Presidente del Consejo Superior \u00a0de la Judicatura y Carlos Enrique Mar\u00edn V\u00e9lez, Magistrado de la Sala \u00a0Administrativa del Consejo Superior de la Judicatura, a participar en el II el \u00a0Encuentro de Consejos de la Judicatura, que se realizar\u00e1 en la ciudad de \u00a0Barcelona (Espa\u00f1a) del 26 al 28 de marzo del a\u00f1o en curso. \u00a0 \u00a0<\/p>\n<p>Que la invitaci\u00f3n comprende el pago de una beca para apoyar \u00a0los gastos de participaci\u00f3n en el evento. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. El presente decreto rige a partir de su \u00a0expedici\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese, comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 8 de marzo de 2001. \u00a0 \u00a0<\/p>\n<p>Romulo Gonzalez Trujillo \u00a0 \u00a0<\/p>\n<p>El Ministro de Justicia y del Derecho, \u00a0 \u00a0<\/p>\n<p>R\u00f3mulo \u00a0Gonz\u00e1lez Trujillo. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0 DECRETO 363 DE \u00a02001 \u00a0 \u00a0 (marzo 8) \u00a0 \u00a0 por el \u00a0cual se autoriza a unos Magistrados del Consejo Superior de la Judicatura para \u00a0que acepten una invitaci\u00f3n. \u00a0 \u00a0 El Ministro de Justicia y del Derecho de la Rep\u00fablica de \u00a0Colombia, delegatario de funciones presidenciales conforme al Decreto \u00a0313 del 23 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-30417","post","type-post","status-publish","format-standard","hentry","category-decretos-2001"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/30417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=30417"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/30417\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=30417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=30417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=30417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}