{"id":30537,"date":"2023-07-18T21:47:38","date_gmt":"2023-07-18T21:47:38","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/18\/decreto-722-de-2001\/"},"modified":"2023-07-18T21:47:38","modified_gmt":"2023-07-18T21:47:38","slug":"decreto-722-de-2001","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/18\/decreto-722-de-2001\/","title":{"rendered":"DECRETO 722 DE 2001"},"content":{"rendered":"\n<p>DECRETO 722 DE \u00a02001 \u00a0 \u00a0<\/p>\n<p>(abril \u00a026) \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>por el cual se autoriza a un Magistrado de la Corte \u00a0Suprema de Justicia para que acepte una invitaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>El Ministro de Justicia y del \u00a0Derecho de la Rep\u00fablica de Colombia, Delegatario de funciones Presidenciales \u00a0conforme al Decreto \u00a0697 del 17 de abril de 2001, en ejercicio de las facultades conferidas por \u00a0los\u2011art\u00edculos 129 y 189 numeral 18 de la Constituci\u00f3n \u00a0Pol\u00edtica, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que la Organizaci\u00f3n de la VI \u00a0Cumbre Iberoamericana de Presidentes de Tribunales y Cortes Supremas de \u00a0Justicia ha formulado invitaci\u00f3n al doctor Jorge Antonio Castillo Rugeles, \u00a0Presidente de la Corte Suprema de Justicia, para participar en la VI Cumbre \u00a0Iberoamericana de Presidentes de Tribunales y Cortes Supremas de Justicia, a \u00a0celebrarse en la Ciudad de Santa Cruz de Tenerife (Espa\u00f1a) del 22 al 26 de mayo \u00a0del a\u00f1o en curso; \u00a0 \u00a0<\/p>\n<p>Que la invitaci\u00f3n comprende el \u00a0pago de los gastos de manutenci\u00f3n y alojamiento que ocasione la participaci\u00f3n \u00a0en el mencionado evento y los gastos de transporte ser\u00e1n cubiertos por la Rama \u00a0Judicial; \u00a0 \u00a0<\/p>\n<p>Que para la Corte Suprema de \u00a0Justicia se hace necesaria la participaci\u00f3n del doctor Jorge Antonio Castillo \u00a0Rugeles, Presidente de la Corte Suprema de Justicia; \u00a0 \u00a0<\/p>\n<p>Que de acuerdo con lo dispuesto \u00a0por el art\u00edculo 129 de la Constituci\u00f3n Pol\u00edtica, \u00a0\u201clos servidores p\u00fablicos no podr\u00e1n aceptar cargos, honores o recompensas de \u00a0gobiernos extranjeros u organismos internacionales, ni para celebrar contratos \u00a0con ellos, sin previa autorizaci\u00f3n del Gobierno\u201d; \u00a0 \u00a0<\/p>\n<p>Que en m\u00e9rito de lo expuesto, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Autor\u00edzase al \u00a0doctor Jorge Antonio Castillo Rugeles, Presidente de la Corte Suprema de \u00a0Justicia, para participar en la VI Cumbre Iberoamericana de Presidentes de \u00a0Tribunales y Cortes Supremas de Justicia, a celebrarse en Ciudad de Santa Cruz \u00a0de Tenerife (Espa\u00f1a) del 22 al 26 de mayo del a\u00f1o en curso. \u00a0 \u00a0<\/p>\n<p>L a presente autorizaci\u00f3n se \u00a0concede adem\u00e1s para aceptar el pago de todos los gastos de manutenci\u00f3n y \u00a0alojamiento que ocasione la participaci\u00f3n en el mencionado evento y los gastos \u00a0de transporte que ser\u00e1n cubiertos por la Rama Judicial. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. El presente decreto \u00a0rige a partir de su expedici\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 26 de abril de 2001. \u00a0 \u00a0<\/p>\n<p>ROMULO GONZALEZ TRUJILLO. \u00a0 \u00a0<\/p>\n<p>El Ministro de Justicia y del Derecho, \u00a0 \u00a0<\/p>\n<p>R\u00f3mulo Gonz\u00e1lez Trujillo \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 722 DE \u00a02001 \u00a0 \u00a0 (abril \u00a026) \u00a0 \u00a0 \u00a0 \u00a0 por el cual se autoriza a un Magistrado de la Corte \u00a0Suprema de Justicia para que acepte una invitaci\u00f3n. \u00a0 \u00a0 El Ministro de Justicia y del \u00a0Derecho de la Rep\u00fablica de Colombia, Delegatario de funciones Presidenciales \u00a0conforme al Decreto \u00a0697 del 17 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-30537","post","type-post","status-publish","format-standard","hentry","category-decretos-2001"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/30537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=30537"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/30537\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=30537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=30537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=30537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}