{"id":30585,"date":"2023-07-18T21:47:41","date_gmt":"2023-07-18T21:47:41","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/18\/decreto-881-de-2001\/"},"modified":"2023-07-18T21:47:41","modified_gmt":"2023-07-18T21:47:41","slug":"decreto-881-de-2001","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/18\/decreto-881-de-2001\/","title":{"rendered":"DECRETO 881 DE 2001"},"content":{"rendered":"\n<p>DECRETO 881 DE \u00a02001 \u00a0 \u00a0<\/p>\n<p>(mayo 11) \u00a0 \u00a0<\/p>\n<p>por el cual se promulga el \u201cAcuerdo de Cooperaci\u00f3n y \u00a0Asistencia Judicial en Materia Penal entre el Gobierno de la Rep\u00fablica de \u00a0Colombia y el Gobierno de la Rep\u00fablica de Venezuela\u201d, suscrito en Caracas el veinte (20) de febrero de mil \u00a0novecientos noventa y ocho (1998). \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, en uso de las \u00a0facultades que le otorga el art\u00edculo 189 numeral 2\u00b0 de la Constituci\u00f3n \u00a0Pol\u00edtica de Colombia y en cumplimiento de la Ley 7\u00aa de 1944, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que la Ley 7\u00aa \u00a0del 30 de noviembre de 1944, en su art\u00edculo 1\u00b0 dispone que los Tratados, \u00a0Convenios, Convenciones, Acuerdos, Arreglos u otros actos internacionales \u00a0aprobados por el Congreso, no se considerar\u00e1n vigentes como leyes internas, \u00a0mientras no hayan sido perfeccionados por el Gobierno en su car\u00e1cter de tales, \u00a0mediante el canje de ratificaciones o el dep\u00f3sito de los instrumentos de \u00a0ratificaci\u00f3n, u otra formalidad equivalente; \u00a0 \u00a0<\/p>\n<p>Que la misma ley en su art\u00edculo segundo ordena la \u00a0promulgaci\u00f3n de los tratados y convenios internacionales una vez sea \u00a0perfeccionado el v\u00ednculo internacional que ligue a Colombia; \u00a0 \u00a0<\/p>\n<p>Que el Congreso Nacional, mediante la Ley 567 \u00a0del 2 de febrero de 2000, publicada en el Diario Oficial \u00a0n\u00famero 43.883 del 7 de febrero de 2000, aprob\u00f3 el \u201cAcuerdo de Cooperaci\u00f3n y \u00a0Asistencia Judicial en Materia Penal entre el Gobierno de la Rep\u00fablica de \u00a0Colombia y el Gobierno de la Rep\u00fablica de Venezuela\u201d, suscrito en Caracas el \u00a0veinte (20) de febrero de mil novecientos noventa y ocho (1998); \u00a0 \u00a0<\/p>\n<p>Que la Corte Constitucional, en sentencia C\u20111259\/00 del \u00a020 de septiembre de 2000, declar\u00f3 exequibles la Ley 567 \u00a0del 2 de febrero de 2000 y el \u201cAcuerdo de Cooperaci\u00f3n y Asistencia Judicial \u00a0en Materia Penal entre el Gobierno de la Rep\u00fablica de Colombia y el Gobierno de \u00a0la Rep\u00fablica de Venezuela\u201d, del 20 de febrero de 1998; \u00a0 \u00a0<\/p>\n<p>Que mediante Nota Verbal n\u00famero DA.30370 del 23 de octubre \u00a0de 2000 el Gobierno de la Rep\u00fablica de Colombia notific\u00f3 el cumplimiento de sus \u00a0procedimientos constitucionales, y en el mismo sentido, el Gobierno de la \u00a0Rep\u00fablica Bolivariana de Venezuela remiti\u00f3 la Nota Verbal n\u00famero 00002551 del \u00a019 de diciembre de 2000, siendo recibida por el Gobierno de Colombia el 20 de \u00a0diciembre de 2000, seg\u00fan Nota n\u00famero 547 del 8 de marzo de 2001. En \u00a0consecuencia, el citado instrumento internacional entr\u00f3 en vigor el primero \u00a0(1\u00b0) de febrero de 2001 de acuerdo con lo previsto en el numeral 1 de su \u00a0art\u00edculo 25, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Prom\u00falgase el \u201cAcuerdo de Cooperaci\u00f3n y \u00a0Asistencia Judicial en Materia Penal entre el Gobierno de la Rep\u00fablica de \u00a0Colombia y el Gobierno de la Rep\u00fablica de Venezuela\u201d, suscrito en Caracas el \u00a0veinte (20) de febrero de mil novecientos noventa y ocho (1998). \u00a0 \u00a0<\/p>\n<p>(Para ser transcrito en este lugar, se adjunta fotocopia \u00a0del texto del \u201cAcuerdo de Cooperaci\u00f3n y Asistencia Judicial en Materia Penal \u00a0entre el Gobierno de la Rep\u00fablica de Colombia y el Gobierno de la Rep\u00fablica de \u00a0Venezuela\u201d, suscrito en Caracas el veinte (20) de febrero de mil novecientos \u00a0noventa y ocho (1998). \u00a0 \u00a0<\/p>\n<p>\u00abACUERDO DE COOPERACION Y ASISTENCIA JUDICIAL EN MATERIA \u00a0PENAL ENTRE EL GOBIERNO DE LA REPUBLICA DE COLOMBIA\u00a0<\/p>\n<p>\u00a0 Y EL GOBIERNO DE LA REPUBLICA DE VENEZUELA \u00a0 \u00a0<\/p>\n<p>El Gobierno de la Rep\u00fablica de Colombia y el Gobierno de \u00a0la Rep\u00fablica de Venezuela, en adelante las Partes; \u00a0 \u00a0<\/p>\n<p>Considerando los lazos \u00a0de amistad y cooperaci\u00f3n que nos unen como pa\u00edses vecinos; \u00a0 \u00a0<\/p>\n<p>Reconociendo que la \u00a0lucha contra la delincuencia es una responsabilidad compartida de la comunidad \u00a0internacional y requiere la actuaci\u00f3n conjunta de los Estados; \u00a0 \u00a0<\/p>\n<p>Conscientes de la necesidad de fortalecer los \u00a0mecanismos de cooperaci\u00f3n judicial y asistencia mutua, para evitar el \u00a0incremento de las actividades delictivas; \u00a0 \u00a0<\/p>\n<p>En observancia de sus \u00a0ordenamientos jur\u00eddicos internos; \u00a0 \u00a0<\/p>\n<p>Han convenido lo siguiente: \u00a0 \u00a0<\/p>\n<p>CAPITULO I \u00a0 \u00a0<\/p>\n<p>Disposiciones generales \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0 \u00a0 \u00a0<\/p>\n<p>Objeto y \u00e1mbito de aplicaci\u00f3n \u00a0 \u00a0<\/p>\n<p>1. La Rep\u00fablica de Colombia y la Rep\u00fablica de \u00a0Venezuela, de conformidad con lo dispuesto en el presente Acuerdo y en sus \u00a0respectivos ordenamientos jur\u00eddicos, se comprometen a prestarse la m\u00e1s amplia \u00a0cooperaci\u00f3n y asistencia judicial rec\u00edproca para investigaciones, procesos y \u00a0actuaciones judiciales relacionadas con asuntos penales. \u00a0 \u00a0<\/p>\n<p>2. El presente Acuerdo no faculta a las autoridades o a \u00a0los particulares de la Parte Requirente a realizar en territorio de la Parte \u00a0Requerida funciones que, seg\u00fan las leyes internas, est\u00e9n reservadas a sus \u00a0autoridades, salvo en el caso previsto en el art\u00edculo 14, numeral 3. \u00a0 \u00a0<\/p>\n<p>3. Este Acuerdo no se aplicar\u00e1 a: \u00a0 \u00a0<\/p>\n<p>a) La detenci\u00f3n de personas con el fin de que s ean extraditadas, \u00a0ni a las solicitudes de extradici\u00f3n; \u00a0 \u00a0<\/p>\n<p>b) La ejecuci\u00f3n de sentencias penales incluido el traslado \u00a0de personas condenadas con el objeto de que cumplan sentencia penal. \u00a0 \u00a0<\/p>\n<p>4. El presente Acuerdo se entender\u00e1 celebrado \u00a0exclusivamente con fines de cooperaci\u00f3n y asistencia judicial mutua entre los \u00a0Estados Contratantes. Las disposiciones del presente Acuerdo no generar\u00e1n \u00a0derecho alguno a favor de los particulares en orden a la obtenci\u00f3n, eliminaci\u00f3n \u00a0o exclusi\u00f3n de pruebas o a la obstaculizaci\u00f3n en el cumplimiento de una \u00a0solicitud. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0 \u00a0 \u00a0<\/p>\n<p>Doble incriminaci\u00f3n \u00a0 \u00a0<\/p>\n<p>La asistencia se prestar\u00e1 aun cuando el hecho por el cual \u00a0se procede en la Parte Requirente no sea considerado como delito por la ley de \u00a0la Parte Requerida. \u00a0 \u00a0<\/p>\n<p>No obstante, para la ejecuci\u00f3n de las inspecciones \u00a0judiciales, requisas, registros y medidas cautelares o definitivas sobre \u00a0bienes, la asistencia se prestar\u00e1 solamente si la legislaci\u00f3n de la Parte \u00a0Requerida prev\u00e9 como delito el hecho por el cual se procede en la Parte \u00a0Requirente. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0 \u00a0 \u00a0<\/p>\n<p>Alcance de la asistencia \u00a0 \u00a0<\/p>\n<p>La asistencia comprender\u00e1: \u00a0 \u00a0<\/p>\n<p>a) Notificaci\u00f3n de actos procesales; \u00a0 \u00a0<\/p>\n<p>b) Recepci\u00f3n, pr\u00e1ctica y remisi\u00f3n de pruebas y diligencias \u00a0judiciales, tales como testimonios, declaraciones, peritajes e inspecciones de \u00a0personas, bienes y lugares; \u00a0 \u00a0<\/p>\n<p>c) Localizaci\u00f3n e identificaci\u00f3n de personas; \u00a0 \u00a0<\/p>\n<p>d) Notificaci\u00f3n de personas y peritos para comparecer \u00a0voluntariamente a fin de prestar declaraci\u00f3n o testimonio en la Parte \u00a0Requirente; \u00a0 \u00a0<\/p>\n<p>e) Traslado de personas detenidas a efectos de comparecer \u00a0como testigos en la Parte Requirente o con otros prop\u00f3sitos expresamente \u00a0indicados en la solicitud; \u00a0 \u00a0<\/p>\n<p>f) Medidas cautelares sobre bienes; \u00a0 \u00a0<\/p>\n<p>g) Cumplimiento de otras solicitudes respecto de bienes, \u00a0incluyendo la eventual transferencia del valor de los bienes decomisados de \u00a0manera definitiva en la medida en que sea compatible con su legislaci\u00f3n \u00a0interna; \u00a0 \u00a0<\/p>\n<p>h) Entrega de documentos y otros objetos de prueba; \u00a0 \u00a0<\/p>\n<p>i) Facilitar el ingreso y permitir movilidad interna en el \u00a0territorio del Estado requerido a funcionarios del Estado Requirente, con el \u00a0fin de asistir a la pr\u00e1ctica de las actuaciones descritas en este Acuerdo, \u00a0siempre que el ordenamiento interno del Estado requerido lo permita; \u00a0 \u00a0<\/p>\n<p>j) Cualquier otra forma de asistencia, de conformidad con \u00a0los fines de este Acuerdo, siempre y cuando no sea incompatible con las leyes del \u00a0Estado Requerido. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 4\u00b0 \u00a0 \u00a0<\/p>\n<p>Autoridades centrales \u00a0 \u00a0<\/p>\n<p>1. Las Autoridades Centrales se encargar\u00e1n de presentar y \u00a0recibir por comunicaci\u00f3n directa entre ellas las solicitudes de cooperaci\u00f3n y \u00a0asistencia a las que se refiere el presente Acuerdo. \u00a0 \u00a0<\/p>\n<p>2. Por la Rep\u00fablica de Colombia, con relaci\u00f3n a las \u00a0solicitudes de asistencia enviadas a Colombia, la Autoridad Central ser\u00e1 la \u00a0Fiscal\u00eda General de la Naci\u00f3n. Con relaci\u00f3n a las solicitudes de asistencia \u00a0formuladas por Colombia, la Autoridad Central ser\u00e1 la Fiscal\u00eda General de la \u00a0Naci\u00f3n o el Ministerio de Justicia y del Derecho. \u00a0 \u00a0<\/p>\n<p>3. Por la Rep\u00fablica de Venezuela la Autoridad Central ser\u00e1 \u00a0el Ministerio de Justicia. \u00a0 \u00a0<\/p>\n<p>Las Partes podr\u00e1n, mediante notas diplom\u00e1ticas, comunicar \u00a0las modificaciones en la designaci\u00f3n de las Autoridades Centrales. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 5\u00b0 \u00a0 \u00a0<\/p>\n<p>Autoridades competentes para la solicitud de cooperaci\u00f3n y \u00a0asistencia \u00a0 \u00a0<\/p>\n<p>Para los efectos de este Acuerdo, las solicitudes \u00a0transmitidas por una Autoridad Central de conformidad con el presente Acuerdo \u00a0se basar\u00e1n en requerimientos de cooperaci\u00f3n y asistencia de las autoridades \u00a0competentes de la Parte Requirente, encargadas del enjuiciamiento o de la \u00a0investigaci\u00f3n de los delitos. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 6\u00b0 \u00a0 \u00a0<\/p>\n<p>Denegaci\u00f3n de asistencia \u00a0 \u00a0<\/p>\n<p>1. La Parte Requerida podr\u00e1 denegar la asistencia \u00a0cuando: \u00a0 \u00a0<\/p>\n<p>a) La solicitud de asistencia a juicio del Estado \u00a0Requerido se refiera a un delito pol\u00edtico o conexo con este; \u00a0 \u00a0<\/p>\n<p>b) La persona en relaci\u00f3n con la cual se solicita la \u00a0medida haya sido absuelta o haya cumplido su condena en la Parte Requerida por \u00a0los mismos hechos mencionados en la solicitud o cuando la acci\u00f3n penal se haya \u00a0extinguido; \u00a0 \u00a0<\/p>\n<p>c) El cumplimiento de la solicitud sea contrario a su \u00a0soberan\u00eda, a la seguridad, al orden p\u00fablico o a otros intereses esenciales o \u00a0fundamentales de la Parte Requerida; \u00a0 \u00a0<\/p>\n<p>d) La solicitud de asistencia sea contraria al \u00a0ordenamiento jur\u00eddico de la Parte Requerida o no se ajuste a las disposiciones \u00a0de este Acuerdo; \u00a0 \u00a0<\/p>\n<p>e) La investigaci\u00f3n haya sido iniciada con el objeto de \u00a0procesar o discriminar en cualquier forma a una persona o grupo de personas por \u00a0razones de raza, sexo, condici\u00f3n social, nacionalidad, religi\u00f3n, ideolog\u00eda o \u00a0cualquier otra forma de violaci\u00f3n de derechos humanos. \u00a0 \u00a0<\/p>\n<p>2. Si la Parte Requerida deniega la asistencia, deber\u00e1 \u00a0informarlo a la Parte Requirente por intermedio de su autoridad central, con \u00a0las razones en que se funda, sin perjuicio de lo dispuesto en el art\u00edculo \u00a013.1.b. \u00a0 \u00a0<\/p>\n<p>3. La autoridad competente de la Parte Requerida podr\u00e1 \u00a0denegar, condicionar o diferir el cumplimiento de la solicitud, cuando se \u00a0considere que obstaculiza un procedimiento penal en curso en su territorio. \u00a0 \u00a0<\/p>\n<p>Sobre esas condiciones la Parte Requerida consultar\u00e1 a la \u00a0Parte Requirente por intermedio de las Autoridades Centrales. Si la Parte \u00a0Requirente acepta la cooperaci\u00f3n o asistencia condicionada, la solicitud ser\u00e1 \u00a0cumplida de conformidad con la manera propuesta. \u00a0 \u00a0<\/p>\n<p>CAPITULO II \u00a0 \u00a0<\/p>\n<p>Ejecuci\u00f3n de las solicitudes \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 7\u00b0 \u00a0 \u00a0<\/p>\n<p>Forma y contenido de la solicitud \u00a0 \u00a0<\/p>\n<p>1. La solicitud de asistencia deber\u00e1 formularse por \u00a0escrito. \u00a0 \u00a0<\/p>\n<p>2. La solicitud podr\u00e1 ser anticipada por t\u00e9lex, facs\u00edmil, \u00a0correo electr\u00f3nico u otro medio equivalente, debiendo ser confirmada por \u00a0documento original firmado por la Parte Requirente dentro de los 30 d\u00edas \u00a0siguientes a su for mulaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>3. La solicitud deber\u00e1 contener las siguientes \u00a0indicaciones: \u00a0 \u00a0<\/p>\n<p>a) Identificaci\u00f3n de la Autoridad Competente de la Parte \u00a0Requirente; \u00a0 \u00a0<\/p>\n<p>b) Descripci\u00f3n de los hechos que constituyen el objeto de \u00a0la cooperaci\u00f3n o asistencia y la naturaleza del procedimiento judicial, \u00a0incluyendo los delitos a los que se refiere; \u00a0 \u00a0<\/p>\n<p>c) Descripci\u00f3n de las medidas de cooperaci\u00f3n o asistencia \u00a0solicitadas; \u00a0 \u00a0<\/p>\n<p>d) Motivos por los cuales se solicitan las medidas; \u00a0 \u00a0<\/p>\n<p>e) Referencia a la legislaci\u00f3n aplicable; \u00a0 \u00a0<\/p>\n<p>f) Identidad de las personas sujetas a procedimientos \u00a0judiciales, cuando sean conocidas; \u00a0 \u00a0<\/p>\n<p>g) Plazo dentro del cual la Parte Requirente desea que la \u00a0solicitud sea cumplida. \u00a0 \u00a0<\/p>\n<p>4. Cuando sea necesario, y en la medida de lo posible, la \u00a0solicitud deber\u00e1 tambi\u00e9n incluir: \u00a0 \u00a0<\/p>\n<p>a) Informaci\u00f3n sobre la identidad y lugar de ubicaci\u00f3n de \u00a0las personas a ser notificadas y su relaci\u00f3n con el proceso; \u00a0 \u00a0<\/p>\n<p>b) La descripci\u00f3n exacta del lugar a inspeccionar y la \u00a0identificaci\u00f3n de la persona sometida a examen, as\u00ed como los bienes objeto de \u00a0una medida cautelar o definitiva; \u00a0 \u00a0<\/p>\n<p>c) El texto del interrogatorio a ser formulado para la \u00a0pr\u00e1ctica de la prueba testimonial en la Parte Requerida, as\u00ed como la \u00a0descripci\u00f3n de la forma como deber\u00e1 efectuarse y registrarse cualquier \u00a0testimonio o declaraci\u00f3n; \u00a0 \u00a0<\/p>\n<p>d) La descripci\u00f3n de la forma y procedimientos especiales \u00a0en que se deber\u00e1 cumplir la solicitud, si as\u00ed fuesen requeridos; \u00a0 \u00a0<\/p>\n<p>e) Informaci\u00f3n sobre el pago de los gastos que se \u00a0asignar\u00e1n a la persona cuya presencia se solicite a la Parte Requerida; \u00a0 \u00a0<\/p>\n<p>f) La indicaci\u00f3n de las autoridades de la Parte Requirente \u00a0que participar\u00e1n en el proceso que se desarrolla en la Parte Requerida; \u00a0 \u00a0<\/p>\n<p>g) Cualquier otra informaci\u00f3n que pueda ser de utilidad a \u00a0la Parte Requerida para facilitar el cumplimiento de la solicitud; \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 8\u00b0 \u00a0 \u00a0<\/p>\n<p>Ley aplicable \u00a0 \u00a0<\/p>\n<p>1. El cumplimiento de las solicitudes se realizar\u00e1 seg\u00fan \u00a0la ley de la Parte Requerida y de conformidad con las disposiciones del \u00a0presente Acuerdo. \u00a0 \u00a0<\/p>\n<p>2. A petici\u00f3n de la Parte Requirente, la Parte Requerida \u00a0cumplir\u00e1 la cooperaci\u00f3n o asistencia de acuerdo con las formas y procedimientos \u00a0especiales indicados en la solicitud, a menos que sean incompatibles con su \u00a0legislaci\u00f3n interna. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 9\u00b0 \u00a0 \u00a0<\/p>\n<p>Confidencialidad y limitaciones en el empleo de la \u00a0informaci\u00f3n \u00a0 \u00a0<\/p>\n<p>1. La Parte Requerida mantendr\u00e1 bajo reserva la solicitud de \u00a0asistencia judicial, salvo que su levantamiento sea necesario para ejecutar el \u00a0requerimiento. En este caso, la Parte Requerida solicitar\u00e1 su aprobaci\u00f3n a la \u00a0Parte Requirente, mediante comunicaci\u00f3n escrita, sin la cual no se ejecutar\u00e1 la \u00a0solicitud. \u00a0 \u00a0<\/p>\n<p>2. La Autoridad Competente de la Parte Requerida podr\u00e1 \u00a0solicitar que la informaci\u00f3n o la prueba obtenida en virtud del presente \u00a0Acuerdo tenga car\u00e1cter confidencial, de conformidad con las condiciones que se \u00a0especifiquen. \u00a0 \u00a0<\/p>\n<p>En tal caso, la Parte Requirente respetar\u00e1 tales \u00a0condiciones. Si no puede aceptarlas, notificar\u00e1 a la Parte Requerida, que \u00a0decidir\u00e1 sobre la solicitud de cooperaci\u00f3n o asistencia. \u00a0 \u00a0<\/p>\n<p>3. Salvo autorizaci\u00f3n previa de la Autoridad Central de la \u00a0Parte Requerida, la Parte Requirente solamente podr\u00e1 emplear la informaci\u00f3n o \u00a0la prueba obtenida en virtud del presente Acuerdo en la investigaci\u00f3n o \u00a0procedimiento indicado en la solicitud. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 10 \u00a0 \u00a0<\/p>\n<p>Informaci\u00f3n sobre el tr\u00e1mite de la solicitud \u00a0 \u00a0<\/p>\n<p>1. A solicitud de la Autoridad Central de la Parte \u00a0Requirente, la Autoridad Central de la Parte Requerida informar\u00e1 en un plazo \u00a0razonable sobre el tr\u00e1mite de la solicitud. \u00a0 \u00a0<\/p>\n<p>2. La Autoridad Central de la Parte Requerida informar\u00e1 \u00a0con brevedad el resultado del cumplimiento de la solicitud y remitir\u00e1 toda la \u00a0informaci\u00f3n y las pruebas obtenidas a la Autoridad Central de la Parte \u00a0Requirente. \u00a0 \u00a0<\/p>\n<p>3. Cuando no sea posible cumplir la solicitud, en todo o \u00a0en parte, la Autoridad Central de la Parte Requerida lo har\u00e1 saber \u00a0inmediatamente a la Autoridad Central de la Parte Requirente e informar\u00e1 las \u00a0razones por las cuales no fue posible su cumplimiento, sin perjuicio de lo \u00a0dispuesto en el art\u00edculo 13. 1.b. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 11 \u00a0 \u00a0<\/p>\n<p>Gastos \u00a0 \u00a0<\/p>\n<p>La Parte Requerida se encargar\u00e1 de los gastos ordinarios \u00a0de diligenciamiento de la solicitud. La Parte Requirente pagar\u00e1 los gastos y \u00a0honorarios correspondientes a los peritos, as\u00ed como los gastos extraordinarios \u00a0en que haya que incurrir para el cumplimiento de la solicitud y los gastos de \u00a0viaje de las personas indicadas en los art\u00edculos 15 y 16. \u00a0 \u00a0<\/p>\n<p>CAPITULO III \u00a0 \u00a0<\/p>\n<p>Formas de cooperaci\u00f3n o asistencia \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 12 \u00a0 \u00a0<\/p>\n<p>Notificaciones y entrega de documentos \u00a0 \u00a0<\/p>\n<p>1. La Autoridad Competente del Estado requerido tomar\u00e1 \u00a0todas las medidas necesarias para efectuar notificaciones, citaciones o entrega \u00a0de documentos relacionados, total o parcialmente, con una solicitud de \u00a0cooperaci\u00f3n o asistencia realizada por la Autoridad Competente del Estado \u00a0Requirente, con arreglo a las disposiciones del presente Acuerdo. \u00a0 \u00a0<\/p>\n<p>2. Cualquier solicitud para la notificaci\u00f3n, citaci\u00f3n o \u00a0entrega de un documento que exija la presencia de una persona ante las \u00a0autoridades del Estado Requirente, deber\u00e1 ser remitida por la Autoridad Central \u00a0del Estado Requerido con suficiente antelaci\u00f3n a la fecha de la cita fijada. \u00a0 \u00a0<\/p>\n<p>3. La Autoridad Central del Estado Requerido deber\u00e1 \u00a0remitir un comprobante de entrega en la forma indicada en la solicitud. \u00a0 \u00a0<\/p>\n<p>4. Si la notificaci\u00f3n o citaci\u00f3n no se realiza, la Parte \u00a0Requerida deber\u00e1 informar, por intermedio de las Autoridades Centrales, a la \u00a0Autoridad Competente de la Parte Requirente, las razones por las cuales no se \u00a0pudo diligenciar. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 13 \u00a0 \u00a0<\/p>\n<p>Entrega y devoluci\u00f3n de documentos oficiales \u00a0 \u00a0<\/p>\n<p>1. Por solicitud de la Autoridad Competente de la Parte \u00a0Requirente, la Autoridad Competente de la Parte Requerida, por intermedio de \u00a0las Autoridades Centrales: \u00a0 \u00a0<\/p>\n<p>a) Proporcionar\u00e1 copia de documentos of\u00edciales, registros \u00a0e informaciones accesibles al p\u00fablico; \u00a0 \u00a0<\/p>\n<p>b) Podr\u00e1 proporcionar copias de documentos e informaciones \u00a0a las que no tenga acceso el p\u00fablico, en las mismas condiciones en las cuales \u00a0esos documentos se pondr\u00edan a disposici\u00f3n de sus propias autoridades. Si la \u00a0asistencia prevista en este literal es denegada, la Autoridad Competente de la \u00a0Parte Requerida no estar\u00e1 obligada a exp resar los motivos de denegaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>2. Los documentos u objetos que hubieran sido enviados en \u00a0cumplimiento de una solicitud de asistencia judicial, deber\u00e1n ser devueltos por \u00a0la Autoridad Competente de la Parte Requirente, cuando la Parte Requerida as\u00ed \u00a0lo solicite. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 14 \u00a0 \u00a0<\/p>\n<p>Asistencia en la parte requerida \u00a0 \u00a0<\/p>\n<p>1. La Autoridad Central de la Parte Requerida, de \u00a0conformidad con su legislaci\u00f3n, deber\u00e1 tomar las medidas necesarias para que \u00a0toda persona que se encuentre en su territorio y a la que se le solicite rendir \u00a0testimonio o peritaje, presentar documentos, antecedentes o elementos de prueba \u00a0en virtud de este Acuerdo, sea citada y si fuese necesario compelida a \u00a0comparecer ante su Autoridad Competente. \u00a0 \u00a0<\/p>\n<p>2. La Parte Requerida informar\u00e1 con suficiente antelaci\u00f3n \u00a0el lugar y la fecha en que se recibir\u00e1 la declaraci\u00f3n testimoniada o peritaje, \u00a0o los documentos mencionados, antecedentes o elementos de prueba. Cuando sea \u00a0necesario, las Autoridades Competentes se consultar\u00e1n por intermedio de las \u00a0Autoridades Centrales para efectos de fijar una fecha conveniente para las \u00a0Autoridades Competentes de las Partes. \u00a0 \u00a0<\/p>\n<p>3. La Autoridad Competente de la Parte Requerida \u00a0autorizar\u00e1 bajo su direcci\u00f3n, la presencia de funcionarios de las autoridades \u00a0de la Parte Requirente indicadas en la solicitud durante el cumplimiento de \u00a0diligencias de cooperaci\u00f3n o asistencia, y permitir\u00e1 formular preguntas si no \u00a0es contrario a su legislaci\u00f3n. La audiencia tendr\u00e1 lugar seg\u00fan los \u00a0procedimientos establecidos por la legislaci\u00f3n de la Parte Requerida. \u00a0 \u00a0<\/p>\n<p>4. Si la persona referida en el numeral 1 alega inmunidad, \u00a0privilegio o incapacidad seg\u00fan la legislaci\u00f3n de la Parte Requerida, esto ser\u00e1 \u00a0resuelto por la Autoridad Competente de la Parte Requerida antes del \u00a0cumplimiento de la solicitud, y se comunicar\u00e1 a la Parte Requirente a trav\u00e9s de \u00a0la Autoridad Central. \u00a0 \u00a0<\/p>\n<p>5. Los documentos, antecedentes y elementos de prueba \u00a0entregados por los declarantes u obtenidos como resultado de su declaraci\u00f3n o \u00a0en ocasi\u00f3n de la misma, ser\u00e1n enviados a la Parte Requirente conjuntamente con \u00a0la declaraci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 15 \u00a0 \u00a0<\/p>\n<p>Asistencia en la parte requirente \u00a0 \u00a0<\/p>\n<p>1. Cuando la Parte Requirente solicite la presencia de una \u00a0persona en su territorio para rendir testimonio u ofrecer informaci\u00f3n o \u00a0declaraci\u00f3n, la Parte Requerida invitar\u00e1 al declarante o perito a comparecer \u00a0ante la Autoridad Competente de la Parte Requirente. \u00a0 \u00a0<\/p>\n<p>2. La Autoridad Competente de la Parte Requerida \u00a0registrar\u00e1 por escrito el consentimiento de la persona cuya presencia es \u00a0solicitada en la Parte Requirente, e informar\u00e1 de inmediato a la Autoridad \u00a0Central de la Parte Requirente sobre la respuesta. \u00a0 \u00a0<\/p>\n<p>3. La Parte Requirente sufragar\u00e1 los gastos de traslado y \u00a0de estad\u00eda a su cargo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 16 \u00a0 \u00a0<\/p>\n<p>Comparecencia de personas detenidas \u00a0 \u00a0<\/p>\n<p>1. A solicitud de la Parte Requirente, y siempre que la \u00a0Parte Requerida acceda, podr\u00e1 procederse a trasladar temporalmente a la Parte \u00a0Requirente, con el objeto de que preste testimonio o asistencia en \u00a0investigaciones, a las personas detenidas en territorio de la Parte Requerida, \u00a0siempre que consientan en ello. \u00a0 \u00a0<\/p>\n<p>2. El traslado ser\u00e1 denegado cuando, seg\u00fan las \u00a0circunstancias del caso, la Autoridad Competente de la Parte Requerida \u00a0considere inconveniente el traslado, entre otras por las siguientes razones: \u00a0 \u00a0<\/p>\n<p>a) La presencia de la persona det enida sea necesaria en \u00a0un proceso penal en curso en el territorio de la Parte Requerida; \u00a0 \u00a0<\/p>\n<p>b) El traslado pueda implicar la prolongaci\u00f3n de la \u00a0detenci\u00f3n preventiva. \u00a0 \u00a0<\/p>\n<p>3. La Parte Requirente mantendr\u00e1 bajo custodia a la \u00a0persona trasladada y la entregar\u00e1 a la Parte Requerida dentro del periodo fijado \u00a0por \u00e9sta, o antes de ello, en la medida en que ya no fuese necesaria su \u00a0presencia. \u00a0 \u00a0<\/p>\n<p>4. El tiempo en que la persona estuviera fuera del \u00a0territorio de la Parte Requerida ser\u00e1 computado para efectos de detenci\u00f3n \u00a0preventiva o cumplimiento de pena. \u00a0 \u00a0<\/p>\n<p>5. En caso de que la persona trasladada ya no deba \u00a0permanecer detenida, la Parte Requerida lo comunicar\u00e1 a la Parte Requirente. \u00a0Esa persona ser\u00e1 puesta en libertad y sometida al r\u00e9gimen general establecido \u00a0en el art\u00edculo 15 del presente Acuerdo. \u00a0 \u00a0<\/p>\n<p>6. La persona detenida que no otorgue su consentimiento \u00a0para prestar declaraciones en los t\u00e9rminos de este art\u00edculo, no estar\u00e1 sujeta, \u00a0por esta raz\u00f3n, a cualquier sanci\u00f3n ni ser\u00e1 sometida a ninguna medida \u00a0conminatoria. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 17 \u00a0 \u00a0<\/p>\n<p>Garant\u00eda temporal \u00a0 \u00a0<\/p>\n<p>1. La comparecencia de una persona que consienta en rendir \u00a0testimonio o prestar asistencia, seg\u00fan lo dispuesto en los art\u00edculos 15 y 16, \u00a0estar\u00e1 condicionada a que la Parte Requirente conceda una garant\u00eda temporal \u00a0por la cual \u00e9sta no podr\u00e1 mientras se \u00a0encuentre la persona en su territorio: \u00a0 \u00a0<\/p>\n<p>b) Detener o juzgar a la persona por delitos anteriores a \u00a0la salida del territorio de la Parte Requerida; \u00a0 \u00a0<\/p>\n<p>b) Citar a la persona a comparecer o a rendir testimonio \u00a0en procedimiento diferente al especificado en la solicitud; salvo que la \u00a0persona manifieste su consentimiento por escrito y las Autoridades Centrales de \u00a0ambos Estados concuerden en ello. \u00a0 \u00a0<\/p>\n<p>2. La garant\u00eda temporal cesar\u00e1 cuando la persona prolongue \u00a0voluntariamente su estad\u00eda en el territorio de la Parte Requirente por m\u00e1s de \u00a010 d\u00edas, a partir del momento en que su presencia no sea necesaria en ese \u00a0Estado, de conformidad con lo comunicado a la Parte Requerida, salvo \u00a0circunstancias de fuerza mayor o caso fortuito. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 18 \u00a0 \u00a0<\/p>\n<p>Medidas cautelares \u00a0 \u00a0<\/p>\n<p>1. Para los fines del presente Acuerdo. \u00a0 \u00a0<\/p>\n<p>a) \u201cProducto del Delito\u201d significa bienes de cualquier \u00a0\u00edndole derivados u obtenidos directa o indirectamente de la comisi\u00f3n de un \u00a0delito o su valor equivalente; \u00a0 \u00a0<\/p>\n<p>b) \u201cInstrumento del Delito\u201d significa cualquier bien \u00a0utilizado o destinado a ser utilizado para la comisi\u00f3n de un delito. \u00a0 \u00a0<\/p>\n<p>2. La Autoridad Competente de una Parte, por conducto de \u00a0las Autoridades Centrales, podr\u00e1 solicitar la identificaci\u00f3n y\/o la adopci\u00f3n de \u00a0medidas cautelares sobre bienes, instrumento o producto de un delito que se \u00a0encuentren ubicados en el territorio de la otra Parte. \u00a0 \u00a0<\/p>\n<p>Cuando se trate de la identificaci\u00f3n del producto del \u00a0delito, la Parte Requerida informar\u00e1 acerca del resultado de la b\u00fasqueda. \u00a0 \u00a0<\/p>\n<p>3. Una vez identificado el producto del delito, o cuando \u00a0se trate del instrumento del delito, a solicitud de la Parte Requirente, la \u00a0Parte Requerida, en la medida en que su legislaci\u00f3n interna lo permita, \u00a0adoptar\u00e1 las medidas cautelares correspondientes sobre tales bienes. \u00a0 \u00a0<\/p>\n<p>4. El requerimiento efectuado en virtud del p\u00e1rraf o \u00a0anterior deber\u00e1 incluir: \u00a0 \u00a0<\/p>\n<p>a) Una copia de la medida cautelar solicitada; \u00a0 \u00a0<\/p>\n<p>b) Un resumen de los hechos del caso, incluyendo una \u00a0descripci\u00f3n del delito, d\u00f3nde y cu\u00e1ndo se cometi\u00f3 y una referencia a las \u00a0disposiciones legales pertinentes; \u00a0 \u00a0<\/p>\n<p>c) En la medida de lo posible, descripci\u00f3n de los bienes \u00a0respecto de los cuales se pretende efectuar la medida y su valor comercial, y \u00a0la relaci\u00f3n de estos con la persona contra la que se inici\u00f3; \u00a0 \u00a0<\/p>\n<p>d) Una estimaci\u00f3n de la suma a la que se pretende aplicar \u00a0la medida cautelar y de los fundamentos del c\u00e1lculo de la misma. \u00a0 \u00a0<\/p>\n<p>5. La Parte Requerida resolver\u00e1, seg\u00fan su legislaci\u00f3n, \u00a0cualquier solicitud relativa a la protecci\u00f3n de derechos de terceros de buena \u00a0fe sobre los bienes que sean materia de las medidas previstas en los p\u00e1rrafos \u00a0anteriores. \u00a0 \u00a0<\/p>\n<p>6. Las Autoridades Competentes de cada una de las Partes \u00a0informar\u00e1n con prontitud sobre el ejercicio de cualquier recurso o de una \u00a0decisi\u00f3n adoptada respecto de la medida cautelar solicitada o adoptada. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 19 \u00a0 \u00a0<\/p>\n<p>Otras medidas de cooperaci\u00f3n y asistencia \u00a0 \u00a0<\/p>\n<p>Las Partes de conformidad con su legislaci\u00f3n interna \u00a0podr\u00e1n prestarse cooperaci\u00f3n y asistencia en el cumplimiento de medidas \u00a0definitivas sobre bienes vinculados a la comisi\u00f3n de un hecho il\u00edcito en \u00a0cualquiera de las Partes. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 20 \u00a0 \u00a0<\/p>\n<p>Custodia y disposici\u00f3n de bienes \u00a0 \u00a0<\/p>\n<p>El Estado Parte que tenga bajo su custodia los \u00a0instrumentos, o el producto del delito, dispondr\u00e1 de los mismos de conformidad \u00a0con lo establecido en su legislaci\u00f3n interna. En la medida que lo permita su \u00a0legislaci\u00f3n y en los t\u00e9rminos que se consideren adecuados, dicho Estado Parte \u00a0podr\u00e1 repartir con el otro los bienes decomisados o el producto de su venta. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 21 \u00a0 \u00a0<\/p>\n<p>Responsabilidad \u00a0 \u00a0<\/p>\n<p>1. La responsabilidad por da\u00f1os que pudieran derivarse de \u00a0los actos de sus autoridades en la ejecuci\u00f3n de este Acuerdo, ser\u00e1 regida por \u00a0la legislaci\u00f3n interna de cada Parte. \u00a0 \u00a0<\/p>\n<p>2. Una de las Partes no ser\u00e1 responsable por los da\u00f1os que \u00a0puedan resultar de actos de las autoridades de la otra Parte, en la formulaci\u00f3n \u00a0o ejecuci\u00f3n de una solicitud, de conformidad con este Acuerdo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 22 \u00a0 \u00a0<\/p>\n<p>Autenticaci\u00f3n de documentos y certificados \u00a0 \u00a0<\/p>\n<p>Los documentos provenientes de una de las Partes, que \u00a0deban ser presentados en el territorio de la otra Parte, que se tramiten por \u00a0intermedio de las Autoridades Centrales, no requerir\u00e1n de autenticaci\u00f3n o cualquier \u00a0otra formalidad an\u00e1loga. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 23 \u00a0 \u00a0<\/p>\n<p>Soluci\u00f3n de controversias \u00a0 \u00a0<\/p>\n<p>1. Cualquier controversia que surja de una solicitud, ser\u00e1 \u00a0resuelta por consulta entre las Autoridades Centrales. \u00a0 \u00a0<\/p>\n<p>2. Cualquier controversia que surja entre las Partes \u00a0relacionada con la interpretaci\u00f3n o aplicaci\u00f3n de este Acuerdo ser\u00e1 resuelta \u00a0por consulta entre las Partes por v\u00eda diplom\u00e1tica. \u00a0 \u00a0<\/p>\n<p>CAPITULO IV \u00a0 \u00a0<\/p>\n<p>Disposiciones finales \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 24 \u00a0 \u00a0<\/p>\n<p>Compatibilidad con otros tratados, acuerdos u otras formas \u00a0de cooperaci\u00f3n o asistencia \u00a0 \u00a0<\/p>\n<p>1. La cooperaci\u00f3n o asistencia establecida en el presente \u00a0Acuerdo no impedir\u00e1 que cada una de las Partes preste cooperaci\u00f3n o asistencia \u00a0a la otra al amparo de lo previsto en otros instrumentos internacionales \u00a0vigentes entre ellas. \u00a0 \u00a0<\/p>\n<p>2. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Este \u00a0Acuerdo no impedir\u00e1 a las Partes la posibilidad de desarrollar otras formas de \u00a0cooperaci\u00f3n o asistencia de conformidad con sus respectivos ordenamientos \u00a0jur\u00eddicos. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 25 \u00a0 \u00a0<\/p>\n<p>Entrada en vigor y duraci\u00f3n \u00a0 \u00a0<\/p>\n<p>1. Las Partes se notificar\u00e1n por v\u00eda diplom\u00e1tica, el \u00a0cumplimiento de los procedimientos constitucionales requeridos en lo que \u00a0concierne a la entrada en vigor del presente Acuerdo, la que tendr\u00e1 lugar el \u00a0primer d\u00eda del segundo mes siguiente a la fecha recepci\u00f3n de la \u00faltima \u00a0notificaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>2. El presente Acuerdo permanecer\u00e1 en vigor \u00a0indefinidamente. \u00a0 \u00a0<\/p>\n<p>3. El presente Acuerdo podr\u00e1 ser denunciado por cualquiera \u00a0de las Partes en cualquier momento, mediante Nota Diplom\u00e1tica, la cual surtir\u00e1 \u00a0efectos seis (6) meses despu\u00e9s de la fecha de recepci\u00f3n por la otra Parte. La \u00a0denuncia no afectar\u00e1 las solicitudes de asistencia en curso. \u00a0 \u00a0<\/p>\n<p>Suscrito en Caracas a los veinte d\u00edas del mes de febrero \u00a0de mil novecientos noventa y ocho en dos ejemplares en idioma espa\u00f1ol, siendo \u00a0ambos textos igualmente v\u00e1lidos y aut\u00e9nticos. \u00a0 \u00a0<\/p>\n<p>Por el Gobierno de la Rep\u00fablica de Colombia, \u00a0 \u00a0<\/p>\n<p>Mar\u00eda Emma Mej\u00eda V\u00e9lez, \u00a0 \u00a0<\/p>\n<p>Ministra de Relaciones \u00a0Exteriores. \u00a0 \u00a0<\/p>\n<p>Por el Gobierno de la Rep\u00fablica de Venezuela, \u00a0 \u00a0<\/p>\n<p>Miguel Angel Burelli Rivas, \u00a0 \u00a0<\/p>\n<p>Ministro de Relaciones \u00a0Exteriores. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. El presente decreto rige a partir de la fecha \u00a0de su publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 11 de mayo de 2001. \u00a0 \u00a0<\/p>\n<p>ANDRES PASTRANA ARANDO \u00a0 \u00a0<\/p>\n<p>El Ministro de Relaciones Exteriores, \u00a0 \u00a0<\/p>\n<p>Guillermo Fern\u00e1ndez de Soto. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 881 DE \u00a02001 \u00a0 \u00a0 (mayo 11) \u00a0 \u00a0 por el cual se promulga el \u201cAcuerdo de Cooperaci\u00f3n y \u00a0Asistencia Judicial en Materia Penal entre el Gobierno de la Rep\u00fablica de \u00a0Colombia y el Gobierno de la Rep\u00fablica de Venezuela\u201d, suscrito en Caracas el veinte (20) de febrero de mil \u00a0novecientos noventa y ocho [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-30585","post","type-post","status-publish","format-standard","hentry","category-decretos-2001"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/30585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=30585"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/30585\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=30585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=30585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=30585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}