{"id":34724,"date":"2023-07-26T19:47:55","date_gmt":"2023-07-26T19:47:55","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-1338-de-2003\/"},"modified":"2023-07-26T19:47:55","modified_gmt":"2023-07-26T19:47:55","slug":"decreto-1338-de-2003","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-1338-de-2003\/","title":{"rendered":"DECRETO 1338 DE 2003"},"content":{"rendered":"\n<p>DECRETO 1338 DE 2003 \u00a0 \u00a0<\/p>\n<p>(mayo 27) \u00a0 \u00a0<\/p>\n<p>por el cual se reglamenta parcialmente el art\u00edculo 63 de \u00a0la Ley 788 de 2002. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, en ejercicio de \u00a0sus facultades constitucionales y legales, en especial de las que le confiere \u00a0el numeral 11 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Para efectos del art\u00edculo 19 de la Ley 9\u00aa de 1991, \u00a0modificado por el art\u00edculo 63 de la Ley 788 de 2002, los \u00a0Precios Representativos del Caf\u00e9 Suave Colombiano por concepto de exportaciones \u00a0de caf\u00e9 verde que se utilizar\u00e1n para calcular la contribuci\u00f3n cafetera \u00a0correspondiente a cada mes de embarque, se determinar\u00e1n de la siguiente manera: \u00a0 \u00a0<\/p>\n<p>a) Para cada d\u00eda de mercado, se tomar\u00e1 el precio de cierre \u00a0de la posici\u00f3n relevante del Contrato \u00abC\u00bb en la Bolsa del Caf\u00e9, Cacao y Az\u00facar \u00a0de Nueva York, la cual ser\u00e1 determinada de acuerdo con el siguiente calendario: \u00a0 \u00a0<\/p>\n<p>Mes de embarque\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Posici\u00f3n relevante Contrato C \u00a0 \u00a0<\/p>\n<p>Enero o febrero\u00a0\u00a0 Marzo \u00a0 \u00a0<\/p>\n<p>Marzo o abril\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Mayo \u00a0 \u00a0<\/p>\n<p>Mayo o junio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Julio \u00a0 \u00a0<\/p>\n<p>Julio o agosto\u00a0\u00a0\u00a0\u00a0 Septiembre \u00a0 \u00a0<\/p>\n<p>Septiembre, octubre o noviembre\u00a0\u00a0 Diciembre \u00a0 \u00a0<\/p>\n<p>Diciembre\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Marzo del a\u00f1o siguiente \u00a0 \u00a0<\/p>\n<p>b) Para cada d\u00eda de mercado, el valor de la prima se \u00a0obtendr\u00e1 restando del Indicador de Precio, OIC, para los Suaves Colombianos, \u00a0disponible para ese d\u00eda, el precio de cierre del contrato C en la Bolsa del Caf\u00e9, \u00a0Cacao y Az\u00facar de Nueva York para la primera posici\u00f3n relevante del mismo d\u00eda; \u00a0 \u00a0<\/p>\n<p>c) Para cada d\u00eda de mercado, el Indicador de Precio Diario \u00a0ser\u00e1 igual a la suma del precio de cierre obtenido seg\u00fan el literal a) \u00a0anterior, para cada posici\u00f3n relevante, y la prima obtenida seg\u00fan el literal b) \u00a0anterior, correspondiente al mismo d\u00eda; \u00a0 \u00a0<\/p>\n<p>d) Para el d\u00eda del anuncio de venta se tomar\u00e1 el Indicador \u00a0de Precio Diario calculado de acuerdo con el literal c) para el d\u00eda de mercado \u00a0inmediatamente anterior, valor que se multiplicar\u00e1 por 0.3; \u00a0 \u00a0<\/p>\n<p>e) Para el d\u00eda del anuncio \u00a0de venta, se obtendr\u00e1 el promedio m\u00f3vil de los Indicadores de Precio Diario \u00a0obtenidos seg\u00fan el literal c) anterior, correspondientes a los 5 d\u00edas de \u00a0mercado precedentes al d\u00eda inmediatamente anterior al d\u00eda del anuncio. El valor \u00a0resultante se multiplicar\u00e1 por 0.7; \u00a0 \u00a0<\/p>\n<p>f) El Precio \u00a0Representativo del Caf\u00e9 Suave Colombiano para el d\u00eda del anuncio de venta \u00a0confirmado por la Federaci\u00f3n Nacional de Cafeteros de Colombia para cada mes de \u00a0embarque, ser\u00e1 igual a la suma de los valores resultantes de los c\u00e1lculos \u00a0previstos en los literales e) y d) de este art\u00edculo. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. En caso de no \u00a0disponerse de alguno de los datos requeridos para determinar el c\u00e1lculo de un \u00a0d\u00eda determinado, la informaci\u00f3n del d\u00eda faltante se descartar\u00e1 para todos los \u00a0efectos. En tal evento, el procedimiento de c\u00e1lculo se efectuar\u00e1 utilizando los \u00a0Indicadores de Precio Diario para los d\u00edas de mercado previos, para los cuales \u00a0se disponga de la informaci\u00f3n completa. En todo caso, se mantendr\u00e1 en seis (6) el \u00a0n\u00famero total de Indicadores de Precio Diario que ser\u00e1n incluidos en el c\u00e1lculo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. La \u00a0liquidaci\u00f3n del valor de la contribuci\u00f3n cafetera se calcular\u00e1 diariamente, \u00a0para cada mes de embarque, con base en el precio referido en el art\u00edculo 1\u00b0 del \u00a0presente decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0. El presente \u00a0decreto rige a partir de su publicaci\u00f3n y deroga las disposiciones que le sean \u00a0contrarias, en especial las contenidas en el Decreto \u00a03263 del 30 de diciembre de 2002. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a \u00a027 de mayo de 2003. \u00a0 \u00a0<\/p>\n<p>\u00c1LVARO URIBE V\u00c9LEZ \u00a0 \u00a0<\/p>\n<p>El Ministro de Hacienda y \u00a0Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Roberto Junguito Bonnet. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 1338 DE 2003 \u00a0 \u00a0 (mayo 27) \u00a0 \u00a0 por el cual se reglamenta parcialmente el art\u00edculo 63 de \u00a0la Ley 788 de 2002. \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, en ejercicio de \u00a0sus facultades constitucionales y legales, en especial de las que le confiere \u00a0el numeral 11 del art\u00edculo 189 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-34724","post","type-post","status-publish","format-standard","hentry","category-decretos-2003"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/34724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=34724"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/34724\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=34724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=34724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=34724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}