{"id":35463,"date":"2023-07-26T20:30:21","date_gmt":"2023-07-26T20:30:21","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-103-de-2004\/"},"modified":"2023-07-26T20:30:21","modified_gmt":"2023-07-26T20:30:21","slug":"decreto-103-de-2004","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-103-de-2004\/","title":{"rendered":"DECRETO 103 DE 2004"},"content":{"rendered":"\n<p>DECRETO 103 DE 2004 \u00a0 \u00a0<\/p>\n<p>(enero 21) \u00a0 \u00a0<\/p>\n<p>por el cual se suprimen cargos vacantes de la planta de \u00a0personal del Departamento Administrativo Nacional de Estad\u00edstica. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, en ejercicio de \u00a0las facultades constitucionales y legales en especial de las que le confiere el \u00a0numeral 14 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica, \u00a0el art\u00edculo 115 de la Ley 489 de 1998, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que el Departamento \u00a0Administrativo Nacional de Estad\u00edstica, present\u00f3 al Departamento Administrativo \u00a0de la Funci\u00f3n P\u00fablica la justificaci\u00f3n t\u00e9cnica de que tratan los art\u00edculos 41 \u00a0de la Ley 443 de 1998 y 148 \u00a0y 155 del Decreto 1572 de 1998, \u00a0modificado por el decreto 2504 de 1998, \u00a0el cual emiti\u00f3 concepto t\u00e9cnico favorable y cuenta con concepto de la Direcci\u00f3n \u00a0General del Presupuesto P\u00fablico Nacional del Ministerio de Hacienda y Cr\u00e9dito \u00a0P\u00fablico, para efectos de modificar su planta de personal, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00ba. Supr\u00edmense de \u00a0la planta de personal de empleados p\u00fablicos del Departamento Administrativo \u00a0Nacional de Estad\u00edstica, los siguientes cargos vacantes: \u00a0 \u00a0<\/p>\n<p>N\u00ba de \u00a0cargos \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0Dependencia y denominaci\u00f3n del empleo\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0C\u00f3digo\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0Grado \u00a0 \u00a0<\/p>\n<p>PLANTA GLOBAL \u00a0 \u00a0<\/p>\n<p>1 (Uno) \u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0Profesional Especializado\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a03010 \u00a0\u00a0\u00a015 \u00a0 \u00a0<\/p>\n<p>1 (Uno)\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0Profesional \u00a0Universitario\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a03020 \u00a0\u00a0\u00a014 \u00a0 \u00a0<\/p>\n<p>1 (Uno)\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0Analista \u00a0de Sistemas\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a04005 \u00a0\u00a0\u00a013 \u00a0 \u00a0<\/p>\n<p>1 (Uno)\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0Asistente \u00a0Administrativo\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a04140 \u00a0\u00a0\u00a015 \u00a0 \u00a0<\/p>\n<p>2 (Dos)\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0Secretario \u00a0Ejecutivo\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a05040 \u00a0\u00a0\u00a018 \u00a0 \u00a0<\/p>\n<p>7 (Siete)\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0Auxiliar Administrativo\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a05120 \u00a0\u00a0\u00a012 \u00a0 \u00a0<\/p>\n<p>2 (Dos)\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0Auxiliar \u00a0Administrativo\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a05120 \u00a0\u00a0\u00a007 \u00a0 \u00a0<\/p>\n<p>1 (Uno)\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0Operario \u00a0Calificado\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a05300 \u00a0\u00a0\u00a011 \u00a0 \u00a0<\/p>\n<p>1 (Uno)\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0Conductor Mec\u00e1nico\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a05310 \u00a0\u00a0\u00a011 \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00ba. El presente decreto \u00a0rige a partir de la fecha de su publicaci\u00f3n y modifica en lo pertinente el Decreto 1187 de 2000. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a \u00a021 de enero de 2004. \u00a0 \u00a0<\/p>\n<p>\u00c1LVARO URIBE V\u00c9LEZ \u00a0 \u00a0<\/p>\n<p>El Viceministro de Hacienda \u00a0y Cr\u00e9dito P\u00fablico encargado de las funciones del Despacho del Ministro de \u00a0Hacienda y Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Juan Ricardo Ortega L\u00f3pez. \u00a0 \u00a0<\/p>\n<p>El Director del \u00a0Departamento Administrativo Nacional de Estad\u00edstica, \u00a0 \u00a0<\/p>\n<p>C\u00e9sar Augusto Caballero Reinoso. \u00a0 \u00a0<\/p>\n<p>El Director del Departamento \u00a0Administrativo de la Funci\u00f3n P\u00fablica, \u00a0 \u00a0<\/p>\n<p>Fernando Grillo Rubiano. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 103 DE 2004 \u00a0 \u00a0 (enero 21) \u00a0 \u00a0 por el cual se suprimen cargos vacantes de la planta de \u00a0personal del Departamento Administrativo Nacional de Estad\u00edstica. \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, en ejercicio de \u00a0las facultades constitucionales y legales en especial de las que le confiere el \u00a0numeral 14 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-35463","post","type-post","status-publish","format-standard","hentry","category-decretos-2004"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/35463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=35463"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/35463\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=35463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=35463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=35463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}