{"id":35721,"date":"2023-07-26T20:30:37","date_gmt":"2023-07-26T20:30:37","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-2337-de-2004\/"},"modified":"2023-07-26T20:30:37","modified_gmt":"2023-07-26T20:30:37","slug":"decreto-2337-de-2004","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-2337-de-2004\/","title":{"rendered":"DECRETO 2337 DE 2004"},"content":{"rendered":"\n<p>DECRETO 2337 DE 2004 \u00a0 \u00a0<\/p>\n<p>(julio 23) \u00a0 \u00a0<\/p>\n<p>por el \u00a0cual se reglamenta la importaci\u00f3n, almacenamiento y distribuci\u00f3n de \u00a0combustibles provenientes de la Rep\u00fablica Bolivariana de Venezuela en las Zonas \u00a0de Frontera del Departamento de Arauca. \u00a0 \u00a0<\/p>\n<p>Nota 1: Ver Decreto 1073 de 2015, \u00a0Decreto \u00danico Reglamentario \u00a0del Sector Administrativo de Minas y Energ\u00eda. \u00a0 \u00a0<\/p>\n<p>Nota 2: Derogado por el Decreto 1475 de 2014, \u00a0art\u00edculo 1\u00ba. \u00a0 \u00a0 \u00a0<\/p>\n<p>Nota 3: Derogado parcialmente \u00a0por el Decreto 2363 de 2006. \u00a0 \u00a0<\/p>\n<p>Nota 4: Modificado por \u00a0el Decreto 4237 de 2004. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, en uso de sus facultades constitucionales \u00a0y legales, en especial las conferidas por los numerales 11 y 25 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica y \u00a0las Leyes 7\u00aa de 1991 y 681 de 2001, previo \u00a0concepto del Comit\u00e9 de Asuntos Aduaneros y Arancelarios, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que de acuerdo con el art\u00edculo 334 de la Constituci\u00f3n Pol\u00edtica, \u00a0la Direcci\u00f3n General de la Econom\u00eda estar\u00e1 a cargo del Estado y este \u00a0intervendr\u00e1, por mandato de la ley, en la explotaci\u00f3n de los recursos \u00a0naturales, en el uso del suelo, en la producci\u00f3n, distribuci\u00f3n, utilizaci\u00f3n y \u00a0consumo de los bienes, y en los servicios p\u00fablicos y privados, para \u00a0racionalizar la econom\u00eda con el fin de conseguir el mejoramiento de la calidad \u00a0de vida de los habitantes, la distribuci\u00f3n equitativa de las oportunidades y \u00a0los beneficios del desarrollo y la preservaci\u00f3n de un ambiente sano; \u00a0 \u00a0<\/p>\n<p>Que el art\u00edculo 337 de la Constituci\u00f3n Pol\u00edtica \u00a0establece que la ley podr\u00e1 establecer para las zonas de frontera terrestres y \u00a0mar\u00edtimas, normas especiales en materias econ\u00f3micas y sociales tendientes a \u00a0promover su crecimiento; \u00a0 \u00a0<\/p>\n<p>Que acorde con los art\u00edculos 285, 289 y 337 de la Constituci\u00f3n Pol\u00edtica de \u00a0Colombia, la Ley 191 de 1995 \u00a0establece un r\u00e9gimen especial para las zonas de frontera, con el fin de \u00a0promover y facilitar su desarrollo econ\u00f3mico, social, cient\u00edfico, tecnol\u00f3gico y \u00a0cultural; \u00a0 \u00a0<\/p>\n<p>Que la Ley 681 de 2001 \u00a0modifica el r\u00e9gimen de concesiones de combustibles l\u00edquidos derivados del \u00a0petr\u00f3leo, excepto GLP, en las zonas de frontera y establece otras disposiciones \u00a0en materia tributaria para los se\u00f1alados combustibles; \u00a0 \u00a0<\/p>\n<p>Que el art\u00edculo 1\u00b0 de la Ley 681 de 2001 prev\u00e9 \u00a0que, en las Zonas de Frontera, Ecopetrol S.A. podr\u00e1 ceder la funci\u00f3n de importaci\u00f3n, \u00a0almacenamiento y distribuci\u00f3n de combustibles l\u00edquidos derivados del petr\u00f3leo a \u00a0los terceros previamente registrados o aprobados por el Ministerio de Minas y \u00a0Energ\u00eda; \u00a0 \u00a0<\/p>\n<p>Que mediante el Decreto 2195 de 2001 \u00a0se reglamenta el art\u00edculo 1\u00b0 de la Ley 681 \u00a0del 9 de agosto de 2001 y se establecen otras disposiciones en materia de \u00a0distribuci\u00f3n de combustibles en zonas de frontera; \u00a0 \u00a0<\/p>\n<p>Que en el Departamento de Arauca existen grupos poblacionales que \u00a0hist\u00f3ricamente han tenido como medio de subsistencia la introducci\u00f3n de \u00a0combustibles provenientes de la Rep\u00fablica de Venezuela al territorio nacional, \u00a0sin el lleno de los requisitos legalmente establecidos para el efecto; \u00a0actividad que, adem\u00e1s de consecuencias graves sobre la distribuci\u00f3n formal de combustibles \u00a0y la seguridad de la misma, viene generando un negativo impacto social y \u00a0econ\u00f3mico para los municipios fronterizos del departamento, por cuanto no est\u00e1n \u00a0recibiendo los recursos provenientes de la sobretasa y, adem\u00e1s, se est\u00e1 \u00a0causando un proceso de descomposici\u00f3n de su tejido social; \u00a0 \u00a0<\/p>\n<p>Que la situaci\u00f3n descrita comporta un problema econ\u00f3mico y social que \u00a0impone la adopci\u00f3n de mecanismos especiales y flexibles para la distribuci\u00f3n de \u00a0combustibles en los municipios calificados como Zona de Frontera en el \u00a0Departamento de Arauca como la celebraci\u00f3n por parte de Ecopetrol S.A. de \u00a0contratos de cesi\u00f3n para la distribuci\u00f3n de combustibles l\u00edquidos derivados del \u00a0petr\u00f3leo prevista en la Ley 681 de 2001; \u00a0 \u00a0<\/p>\n<p>Que en la sesi\u00f3n 124 del 16 de julio de 2004, el Comit\u00e9 de Asuntos \u00a0Aduaneros, Arancelarios y de Comercio Exterior, recomend\u00f3 la aprobaci\u00f3n de la \u00a0reglamentaci\u00f3n para la importaci\u00f3n, distribuci\u00f3n y almacenamiento de \u00a0combustibles, provenientes de la Rep\u00fablica de Venezuela, en las zonas de \u00a0frontera del Departamento de Arauca, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00ba. Modificado por el Decreto 4237 de 2004, \u00a0art\u00edculo 1\u00ba. Campo de aplicaci\u00f3n. El presente decreto aplicar\u00e1 \u00a0exclusivamente para los combustibles l\u00edquidos derivados del petr\u00f3leo (gasolina \u00a0sin plomo y Acpm) que se introduzcan desde la Rep\u00fablica Bolivariana de \u00a0Venezuela, por los sitios previamente establecidos por la Direcci\u00f3n de \u00a0Impuestos y Aduanas Nacionales, DIAN, siempre que los mismos se entreguen a los \u00a0Puntos de Recolecci\u00f3n debidamente aprobados y registrados por la Direcci\u00f3n de \u00a0Hidrocarburos del Ministerio de Minas y Energ\u00eda, para su almacenamiento y venta \u00a0a la Planta de Abastecimiento de propiedad de Ecopetrol S.A., ubicada en el \u00a0municipio de Arauca y a los Centros de Acopio debidamente aprobados y \u00a0registrados como Terceros por el Ministerio de Minas y Energ\u00eda, y habilitados \u00a0como Dep\u00f3sitos por la Direcci\u00f3n de Impuestos y Aduanas Nacionales, DIAN, \u00a0ubicados en el departamento de Arauca. \u00a0 \u00a0<\/p>\n<p>La Planta de Abastecimiento ubicada en el municipio de Arauca y los Centros \u00a0de Acopio ubicados en el departamento de Arauca, tendr\u00e1n la responsabilidad de \u00a0desarrollar el proceso de marcaci\u00f3n, nacionalizar los combustibles ingresados \u00a0de que trata este decreto, recaudar y girar los valores correspondientes a la \u00a0sobretasa, suministrar la gu\u00eda de compra de que trata el presente decreto y la \u00a0gu\u00eda \u00fanica de transporte de combustibles a que se refiere el Decreto 300 de 1993 \u00a0o dem\u00e1s normas que lo modifiquen, aclaren o deroguen. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. Los transportadores de combustibles desde el Punto de \u00a0Recolecci\u00f3n a la Planta de Abastecimiento o el Centro de Acopio, deber\u00e1n portar \u00a0una gu\u00eda de compra, la cual deber\u00e1 ser suministrada por la Planta de \u00a0Abastecimiento o el Centro de Acopio, seg\u00fan corresponda. \u00a0 \u00a0<\/p>\n<p>El Original de la gu\u00eda de compra deber\u00e1 reposar en el Punto de Recolecci\u00f3n \u00a0y las copias en la Planta de Abastecimiento o el Centro de Acopio y la \u00a0Secretar\u00eda de Hacienda del departamento. \u00a0 \u00a0<\/p>\n<p>Las copias de la gu\u00eda de compra deber\u00e1 ser entregado por el transportador a \u00a0la Planta de Abastecimiento o Centro de Acopio, al momento del recibo del \u00a0combustible. La Planta de Abastecimiento o el Centro de Acopio, seg\u00fan \u00a0corresponda, se encargar\u00e1 de enviar a la Secretar\u00eda de Hacienda del \u00a0departamento la copia que le corresponde. \u00a0 \u00a0<\/p>\n<p>La gu\u00eda de compra deber\u00e1 contener, como m\u00ednimo la siguiente informaci\u00f3n: \u00a0numeraci\u00f3n consecutiva, con el logotipo de la Planta de Abastecimiento o Centro \u00a0de Acopio, que la expide impreso al margen izquierdo, tipo y volumen de \u00a0combustible, valor, fecha de expedici\u00f3n y vigencia, informaci\u00f3n del Punto de \u00a0Recolecci\u00f3n, identificaci\u00f3n del veh\u00edculo de transporte, origen, ruta y destino \u00a0del combustible. \u00a0 \u00a0<\/p>\n<p>La gu\u00eda de compra constituir\u00e1 el documento que ampara el traslado de \u00a0combustibles desde el Punto de Recolecci\u00f3n hasta la Planta de Abastecimiento o \u00a0el Centro de Acopio. El Transporte solo podr\u00e1 realizarse en los veh\u00edculos \u00a0carrotanques, previamente informados por la Planta de Abastecimiento o el \u00a0Centro de Acopio a la Direcci\u00f3n de Hidrocarburos del Ministerio de Minas y \u00a0Energ\u00eda y a la Direcci\u00f3n de Impuestos y Aduanas Nacionales, DIAN. \u00a0 \u00a0<\/p>\n<p>La fuerza p\u00fablica y las autoridades de control se\u00f1aladas por la ley, podr\u00e1n \u00a0solicitar al Transportador, la copia de la gu\u00eda de compra que ampara el \u00a0traslado de los combustibles l\u00edquidos derivados del petr\u00f3leo. En el evento en \u00a0que no se porte, deber\u00e1n inmovilizar los veh\u00edculos y ponerlos a disposici\u00f3n de \u00a0las autoridades competentes, sin perjuicio de las acciones que procedan \u00a0respecto de la mercanc\u00eda conforme con las disposiciones especiales y de las \u00a0dem\u00e1s sanciones a que haya lugar. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. La introducci\u00f3n de combustibles l\u00edquidos derivados del \u00a0petr\u00f3leo provenientes de la Rep\u00fablica Bolivariana de Venezuela por sitios \u00a0diferentes a los se\u00f1alados por la Direcci\u00f3n de Impuestos y Aduanas Nacionales y \u00a0el almacenamiento y distribuci\u00f3n en instalaciones que no cuenten con las \u00a0aprobaciones exigidas por las autoridades competentes, dar\u00e1n lugar a la \u00a0configuraci\u00f3n de infracciones administrativas de conformidad con las \u00a0disposiciones especiales, sin perjuicio de las investigaciones penales que \u00a0puedan generarse por los delitos tipificados en los art\u00edculos 70 a 74 de la Ley 788 de 2002, o las \u00a0normas que la modifiquen, adicionen o deroguen. \u00a0 \u00a0<\/p>\n<p>Nota, art\u00edculo 1\u00ba: Ver art\u00edculo 2.2.1.1.2.2.6.7. del Decreto 1073 de 2015, \u00a0Decreto \u00danico Reglamentario \u00a0del Sector Administrativo de Minas y Energ\u00eda. \u00a0 \u00a0<\/p>\n<p>Texto inicial del \u00a0art\u00edculo 1\u00ba: \u201cCampo de aplicaci\u00f3n. El presente decreto aplicar\u00e1 \u00a0exclusivamente para los combustibles l\u00edquidos derivados del petr\u00f3leo (gasolina \u00a0sin plomo y ACPM) que las personas naturales introduzcan desde la Rep\u00fablica \u00a0Bolivariana de Venezuela por los sitios previamente establecidos por la \u00a0Direcci\u00f3n de Impuestos y Aduanas Nacionales, DIAN, siempre y cuando los mismos \u00a0se vendan y almacenen \u00fanicamente en la planta de abastecimiento de combustibles \u00a0l\u00edquidos ubicada en el municipio de Arauca o en Centros de Acopio debidamente \u00a0aprobados y registrados como terceros por el Ministerio de Minas y Energ\u00eda para \u00a0ser distribuidos en los municipios calificados como Zona de Frontera en el \u00a0Departamento de Arauca. \u00a0 \u00a0<\/p>\n<p>Para el efecto, la planta de abastecimiento en menci\u00f3n y los Centros de \u00a0Acopio deber\u00e1n habilitarse ante la DIAN como Dep\u00f3sitos, conforme con las \u00a0disposiciones establecidas en el T\u00edtulo III, Cap\u00edtulo II, art\u00edculo 47 y \u00a0siguientes del Decreto 2685 de 1999 \u00a0y dem\u00e1s normas \u00a0que lo adicionen, modifiquen o aclaren, salvo lo previsto en el literal a) del \u00a0art\u00edculo 51 y en el literal b) del art\u00edculo 71 respecto al valor del patrimonio \u00a0neto a acreditar, el cual para efectos de la habilitaci\u00f3n como dep\u00f3sitos ser\u00e1 \u00a0de una d\u00e9cima parte del valor previsto en las referidas disposiciones. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Quienes introduzcan combustibles l\u00edquidos derivados del \u00a0petr\u00f3leo provenientes de la Rep\u00fablica Bolivariana de Venezuela por sitios \u00a0diferentes a los se\u00f1alados por la DIAN o quienes vendan, almacenen o \u00a0distribuyan los referidos combustibles en lugares diferentes a la planta de \u00a0abastecimiento ubicada en el municipio de Arauca o los Centros de Acopio \u00a0previstos en este Art\u00edculo, estar\u00e1n incursos en los delitos tipificados en los \u00a0art\u00edculos 70 a 74 de la Ley 788 de 2002, o las normas que la \u00a0modifiquen, adicionen o deroguen, sin perjuicio de las dem\u00e1s sanciones a que \u00a0haya lugar.\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00ba. Modificado por el Decreto 4237 de 2004, \u00a0art\u00edculo 2\u00ba. Requisitos para la aprobaci\u00f3n y registro. Las personas \u00a0naturales o jur\u00eddicas interesadas en obtener la aprobaci\u00f3n y registro para la \u00a0operaci\u00f3n de Puntos de Recolecci\u00f3n o como Terceros a trav\u00e9s de Centros de \u00a0Acopio, deber\u00e1n presentar solicitud escrita a la Direcci\u00f3n de Hidrocarburos del \u00a0Ministerio de Minas y Energ\u00eda y cumplir con los siguientes requisitos: \u00a0 \u00a0<\/p>\n<p>I. PUNTOS DE RECOLECCI\u00d3N \u00a0 \u00a0<\/p>\n<p>1. La Direcci\u00f3n de Hidrocarburos del Ministerio de Minas y Energ\u00eda \u00a0\u00fanicamente tramitar\u00e1 las solicitudes para aprobaci\u00f3n como Puntos de Recolecci\u00f3n \u00a0de combustibles l\u00edquidos derivados del petr\u00f3leo que se radiquen en dicha \u00a0entidad durante los tres (3) meses siguientes a la entrada en vigencia del \u00a0presente decreto. \u00a0 \u00a0<\/p>\n<p>2 Deber\u00e1n estar ubicados \u00fanicamente en los municipios de Arauca y Arauquita, \u00a0departamento de Arauca. \u00a0 \u00a0<\/p>\n<p>3. No se permite la existencia de vivienda en el interior del Punto de \u00a0Recolecci\u00f3n de combustibles l\u00edquidos derivados del petr\u00f3leo (gasolina si n \u00a0plomo y Acpm). \u00a0 \u00a0<\/p>\n<p>4. La distancia entre el lugar que se destine para el almacenamiento de los \u00a0combustibles dentro del Punto de Recolecci\u00f3n (tanques o pimpinas) a los \u00a0linderos m\u00e1s pr\u00f3ximos de sitios de alta densidad poblacional, tales como \u00a0escuelas, colegios, universidades, bibliotecas p\u00fablicas, hospitales, cl\u00ednicas, \u00a0supermercados, centros comerciales, cines, teatros, coliseos, polideportivos, \u00a0edificios multifamiliares y establecimientos similares, no podr\u00e1 ser inferior a \u00a0diez (10) metros. \u00a0 \u00a0<\/p>\n<p>5. El almacenamiento de los combustibles (sea en tanques o pimpinas) deber\u00e1 \u00a0efectuarse \u00fanicamente en recintos abiertos de f\u00e1cil acceso, distanciados por lo \u00a0menos diez (10) metros de talleres, garajes u otras instalaciones que por el \u00a0tr\u00e1fico del p\u00fablico o por generaci\u00f3n de calor puedan ofrecer peligro. \u00a0 \u00a0<\/p>\n<p>6. Los Puntos de Recolecci\u00f3n deber\u00e1n contar como m\u00ednimo con dos (2) \u00a0extintores de polvo qu\u00edmico de 20 libras cada uno, por cada trescientos (300) \u00a0metros cuadrados de \u00e1rea del piso, as\u00ed como avisos visibles al p\u00fablico, \u00a0prohibiendo terminantemente fumar o encender cualquier clase de fuego dentro \u00a0del l\u00edmite de almacenamiento. \u00a0 \u00a0<\/p>\n<p>7. El Punto de Recolecci\u00f3n podr\u00e1 almacenar un m\u00ednimo de dos mil (2.000) \u00a0galones y un m\u00e1ximo de diez mil (10.000) galones de combustibles l\u00edquidos \u00a0derivados del petr\u00f3leo (gasolina sin plomo y Acpm). \u00a0 \u00a0<\/p>\n<p>8. El almacenamiento mayor a diez mil (10.000) galones, solo podr\u00e1 \u00a0realizarse en lugares habilitados como Centros de Acopio. \u00a0 \u00a0<\/p>\n<p>9. Inscribirse en el Registro Unico Tributario-RUT-de que trata el art\u00edculo \u00a05\u00b0 del Decreto 2788 de 2004. \u00a0 \u00a0<\/p>\n<p>II. CENTROS DE ACOPIO \u00a0 \u00a0<\/p>\n<p>De conformidad con lo dispuesto en el inciso 2\u00b0 del art\u00edculo 19 de la Ley 191 de 1995, \u00a0modificado por el art\u00edculo 1 \u00b0 de la Ley 681 de 2001, el \u00a0Ministerio de Minas y Energ\u00eda aprobar\u00e1 e inscribir\u00e1 como Terceros a los Centros \u00a0de Acopio ubicados en el departamento de Arauca que, adem\u00e1s de cumplir con lo \u00a0se\u00f1alado en el art\u00edculo 6\u00b0 del Decreto 2195 de 2001, \u00a0cumpla los siguientes requisitos: \u00a0 \u00a0<\/p>\n<p>1. Deber\u00e1n estar ubicados en sitios aleda\u00f1os al paso o cruce de frontera \u00a0del municipio de Arauquita, habilitados como lugares de ingreso por la \u00a0Direcci\u00f3n de Impuestos y Aduanas Nacionales. \u00a0 \u00a0<\/p>\n<p>2. Inscribirse en el Registro Unico Tributario, RUT, de que trata el \u00a0art\u00edculo 5\u00b0 del Decreto 2788 de 2004. \u00a0 \u00a0<\/p>\n<p>3. La distancia de los tanques y las instalaciones de cargue y descargue \u00a0(llenadero) del Centro de Acopio a los linderos m\u00e1s pr\u00f3ximos de sitios de alta \u00a0densidad poblacional, tales como escuelas, colegios, universidades, bibliotecas \u00a0p\u00fablicas, hospitales, cl\u00ednicas, supermercados, centros comerciales, cines, \u00a0teatros, coliseos, polideportivos, edificios multifamiliares y establecimientos \u00a0similares, no podr\u00e1 ser inferior a diez (10) metros. \u00a0 \u00a0<\/p>\n<p>4. Todo tanque o grupo de tanques que contenga combustibles deber\u00e1 estar \u00a0rodeado por un muro de retenci\u00f3n impermeabilizado, que deber\u00e1 construirse en \u00a0concreto, tierra apisonada e impermeabilizada u otro material adecuado. La \u00a0altura m\u00ednima de dicho muro ser\u00e1 de sesenta (60) cent\u00edmetros y la m\u00e1xima de dos \u00a0(2) metros. Si un recinto rodeado por un muro de retenci\u00f3n contiene un solo \u00a0tanque, su capacidad neta ser\u00e1 por lo menos igual a la capacidad del tanque y \u00a0se calcular\u00e1 como si tal tanque no existiera. Esto \u00faltimo teniendo en cuenta que \u00a0en caso de m\u00e1ximo derrame del tanque, quedar\u00e1 en este un nivel l\u00edquido igual a \u00a0la altura del muro de retenci\u00f3n. Si el recinto de retenci\u00f3n contiene dos o m\u00e1s \u00a0tanques, su capacidad neta ser\u00e1 por lo menos igual a la del tanque de mayor \u00a0capacidad dentro del recinto m\u00e1s el diez por ciento (10%) de la capacidad de \u00a0los otros tanques. \u00a0 \u00a0<\/p>\n<p>5. En el interior de los muros de retenci\u00f3n no debe haber ning\u00fan tipo de \u00a0instalaciones diferentes de las estrictamente necesarias para el manejo seguro \u00a0de los combustibles l\u00edquidos derivados del petr\u00f3leo. \u00a0 \u00a0<\/p>\n<p>6. Todas las tuber\u00edas y accesorios, dentro y fuera de los recintos o muros \u00a0de retenci\u00f3n, ser\u00e1n de acero-carb\u00f3n. Las que se instalen dentro deber\u00e1n \u00a0dise\u00f1arse para resistir altas temperaturas. \u00a0 \u00a0<\/p>\n<p>7. Las instalaciones para el cargue (llenadero) y descargue de carrotanques \u00a0deben estar separadas de los tanques, bodegas, otros edificios de la planta o \u00a0del lindero m\u00e1s pr\u00f3ximo sobre el cual existen o pueden existir construcciones, \u00a0por una distancia no menor de siete metros con sesenta cent\u00edmetros (7.6), \u00a0medidos desde la boca de llenado o conexi\u00f3n de transferencia m\u00e1s cercanos. \u00a0 \u00a0<\/p>\n<p>8. Las instalaciones de cargue (llenadero) y descargue deben proveerse de \u00a0sistemas de drenaje u otros medios para contener derrames, as\u00ed como de medios \u00a0para conectarlas el\u00e9ctricamente para protegerlas contra riesgos asociados con \u00a0la electricidad est\u00e1tica. \u00a0 \u00a0<\/p>\n<p>9. Los equipos tales como tuber\u00edas, bombas y medidores empleados para \u00a0transferir gasolinas, no deben usarse para la transferir Diesel (Acpm), a fin \u00a0de evitar contaminaci\u00f3n durante las operaciones de cargue y descargue. \u00a0 \u00a0<\/p>\n<p>10. El Centro de Acopio deber\u00e1 abastecerse \u00fanicamente a trav\u00e9s de \u00a0carrotanques. \u00a0 \u00a0<\/p>\n<p>11. Toda instalaci\u00f3n de cargue (llenadero) deber\u00e1 estar provista, al menos, \u00a0de: \u00a0 \u00a0<\/p>\n<p>a) Dos escaleras, con inclinaci\u00f3n m\u00e1xima de cuarenta y cinco grados (45\u00b0); \u00a0 \u00a0<\/p>\n<p>b) Brazos de llenado, los cuales deben extenderse hasta 15 cent\u00edmetros del \u00a0fondo del tanque del carrotanque, al momento del llenado; c) Se\u00f1ales \u00a0preventivas en colores reflectivos. \u00a0 \u00a0<\/p>\n<p>12. Los equipos contra incendio que deber\u00e1n ser instalados contar\u00e1n como \u00a0m\u00ednimo con: \u00a0 \u00a0<\/p>\n<p>a) Tanque para agua contra incendio; \u00a0 \u00a0<\/p>\n<p>b) Sistema de hidrantes con boquillas monitoras fijas para enfriamiento; \u00a0 \u00a0<\/p>\n<p>c) Contar como m\u00ednimo con los siguientes extintores port\u00e1tiles de mano: \u00a0 \u00a0<\/p>\n<p>\u25aa Casa de bombas: Un extintor de polvo qu\u00edmico de nueve (9) \u00a0kilogramos. \u00a0 \u00a0<\/p>\n<p>\u25aa Instalaciones de cargue (llenadero): Un extintor de polvo \u00a0qu\u00edmico de nueve (9) kilogramos por cada dos brazos de llenado. \u00a0 \u00a0<\/p>\n<p>\u25aa Oficinas: Un extintor multiprop\u00f3sito con una capacidad no \u00a0inferior a cuatro y medio (4.5) kilogramos. Para el equipo electr\u00f3nico un \u00a0extintor de hal\u00f3n o de gas carb\u00f3nico no Inferior a cinco (5) kilogramos de \u00a0capacidad. \u00a0 \u00a0<\/p>\n<p>\u25aa Un extintor port\u00e1til de carretel de polvo qu\u00edmico seco de sesenta y \u00a0ocho (68) kilogramos. \u00a0 \u00a0<\/p>\n<p>13. Contar con un plan de emergencia para casos de derrames, fugas o \u00a0incendio. \u00a0 \u00a0<\/p>\n<p>14.Adquirir una p\u00f3liza de seguro de responsabilidad civil extracontractual, \u00a0en la cual debe aparecer expresamente determinada y ubicada el Centro de Acopio \u00a0asegurado, acompa\u00f1ada del clausulado general con sus correspondientes anexos, \u00a0as\u00ed como copia del recibo de pago, en los montos establecidos en el literal a) \u00a0del art\u00edculo 82 del Decreto 283 de 1990, \u00a0o aquella norma que la derogue, adicione o modifique. \u00a0 \u00a0<\/p>\n<p>15. La distribuci\u00f3n de los tanques y dem\u00e1s instalaciones y su separaci\u00f3n \u00a0con respecto a propiedades adyacentes deber\u00e1 cumplir con las distancias m\u00ednimas \u00a0indicadas en las Tablas siguientes: \u00a0 \u00a0<\/p>\n<p>TABLA 1 \u00a0 \u00a0<\/p>\n<p>PROPIEDADES ADYACENTES PARA EL ALMACENAMIENTO DE COMBUSTIBLES LIQUIDOS \u00a0DERIVADOS DEL PETROLEO \u00a0 \u00a0<\/p>\n<p>L\u00edquidos estables* (Presi\u00f3n de operaci\u00f3n menor de 0.175 Kg\/cm2) \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 1\u00b0. Una vez obtenida la aprobaci\u00f3n como Centro de Acopio de parte \u00a0del Ministerio de Minas y Energ\u00eda, se deber\u00e1 solicitar habilitaci\u00f3n como \u00a0Dep\u00f3sito Privado ante la Direcci\u00f3n de Impuestos y Aduanas Nacionales, conforme \u00a0con las disposiciones establecidas en el T\u00edtulo III, Cap\u00edtulo II, art\u00edculos 47 \u00a0y siguientes del Decreto 2685 de 1999 \u00a0y dem\u00e1s normas que lo adicionen, modifiquen o aclaren, salvo lo previsto en el \u00a0literal a) del art\u00edculo 51 y en el literal b) del art\u00edculo 71 respecto al valor \u00a0del patrimonio neto a acreditar, el cual para efectos de la habilitaci\u00f3n de \u00a0Centros de Acopio como Dep\u00f3sito ser\u00e1 de un cinco por ciento del valor previsto \u00a0en las referidas disposiciones. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. No obstante lo establecido en el art\u00edculo 7\u00b0 del presente \u00a0decreto y con el fin de mantener el orden de prelaci\u00f3n se\u00f1alado en el art\u00edculo \u00a02\u00b0 del Decreto 2195 de 2001, \u00a0en el momento que exista una planta de abastecimiento para almacenamiento y \u00a0distribuci\u00f3n de combustibles l\u00edquidos derivados del petr\u00f3leo (gasolina sin \u00a0plomo y Acpm), en el municipio de Arauquita, el Ministerio de Minas y Energ\u00eda \u00a0se abstendr\u00e1 de aprobar e inscribir como terceros a Centros de Acopio en dicho \u00a0municipio. \u00a0 \u00a0<\/p>\n<p>Una vez entre a operar la planta de abastecimiento de combustibles l\u00edquidos \u00a0derivados del petr\u00f3leo, los Centros de Acopio debidamente aprobados y que se \u00a0encuentren funcionando, se les otorgar\u00e1 un \u00fanico plazo de seis (6) meses, \u00a0contados a partir de la fecha en que quede en firme el acto administrativo \u00a0aprobatorio de entrada en operaci\u00f3n de la planta de abastecimiento, para \u00a0continuar distribuyendo a las estaciones de servicio y grandes consumidores de \u00a0los municipios se\u00f1alados como Zona de Frontera en el Departamento de Arauca. \u00a0 \u00a0<\/p>\n<p>Transcurridos este tiempo, tendr\u00e1n que habilitarse como Plantas de \u00a0Abastecimiento, cumpliendo para el efecto los requisitos exigidos en el \u00a0Cap\u00edtulo II del Decreto 283 de 1990, \u00a0o la norma que lo modifique, adicione o derogue, o en su defecto distribuir los \u00a0combustibles l\u00edquidos derivados del petr\u00f3leo \u00fanica y exclusivamente a trav\u00e9s de \u00a0la Planta de Abastecimiento que exista en dicho departamento, por un periodo \u00a0m\u00e1ximo de doce (12) meses, contados a partir de la finalizaci\u00f3n de los seis (6) \u00a0meses se\u00f1alados en el inciso anterior. \u00a0 \u00a0<\/p>\n<p>Finalizados los doce (12) meses, el Centro de Acopio deber\u00e1 desmantelarse, \u00a0por cuanto el acto administrativo que dio su aprobaci\u00f3n precluye. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 3\u00b0. De acuerdo con el prop\u00f3sito del Gobierno Nacional, Una vez se \u00a0establezca la importaci\u00f3n de combustibles l\u00edquidos derivados del petr\u00f3leo \u00a0(gasolina sin plomo y Acpm) a trav\u00e9s de carrotanques, proveniente de la \u00a0Rep\u00fablica Bolivariana de Venezuela, los Puntos de Recolecci\u00f3n tendr\u00e1n un \u00fanico \u00a0plazo de dos (2) meses, contados a partir de la fecha en que se efect\u00fae la \u00a0importaci\u00f3n en las condiciones previstas en este Par\u00e1grafo, para continuar \u00a0distribuyend o a la Planta de Abastecimiento o los Centros de Acopio. \u00a0 \u00a0<\/p>\n<p>Finalizado dicho per\u00edodo, el Punto de Recolecci\u00f3n deber\u00e1 desmantelarse, por \u00a0cuanto el acto administrativo que dio su aprobaci\u00f3n precluye. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 4\u00b0. Las personas que introduzcan combustibles l\u00edquidos derivados \u00a0del petr\u00f3leo (gasolina sin plomo y Acpm) proveniente de la Rep\u00fablica \u00a0Bolivariana de Venezuela, deber\u00e1n cumplir con las siguientes obligaciones: \u00a0 \u00a0<\/p>\n<p>1. Estar registrados y carnetizados ante una cooperativa legalmente \u00a0constituida. \u00a0 \u00a0<\/p>\n<p>2. Les queda terminantemente prohibido vender los combustibles l\u00edquidos \u00a0derivados del petr\u00f3leo (gasolina sin plomo y Acpm) en sitios diferentes a los \u00a0Puntos de Recolecci\u00f3n debidamente aprobados. \u00a0 \u00a0<\/p>\n<p>3. El tr\u00e1nsito del combustible se limita desde la frontera al Punto de \u00a0Recolecci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 5\u00b0. Sin perjuicio de las disposiciones especiales, la Gobernaci\u00f3n \u00a0del departamento de Arauca tendr\u00e1 la obligaci\u00f3n de ejercer controles a los \u00a0Puntos de Recolecci\u00f3n, con el objeto de determinar los vol\u00famenes adquiridos y \u00a0los despachados a la Planta de Abastecimiento y los diferentes Centros de \u00a0Acopio del departamento. \u00a0 \u00a0<\/p>\n<p>Esta informaci\u00f3n deber\u00e1 reposar en los libros de registro suministrados por \u00a0la Gobernaci\u00f3n del Departamento, a los Puntos de recolecci\u00f3n y Centros de \u00a0Acopio, sin ning\u00fan costo, y debidamente foliados. La Gobernaci\u00f3n informar\u00e1 durante \u00a0los primeros diez (10) d\u00edas de cada mes al Ministerio de Minas y Energ\u00eda, a \u00a0Ecopetrol S.A., y a la Direcci\u00f3n de Impuestos y Aduanas Nacionales, DIAN, los \u00a0vol\u00famenes adquiridos y despachados por cada Punto de Recolecci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Adicionalmente deber\u00e1 supervisar que solamente los Puntos de Recolecci\u00f3n \u00a0que se encuentren debidamente aprobados por el Ministerio de Minas y Energ\u00eda \u00a0sean los que almacenen y distribuyan a la Planta de Abastecimiento y los \u00a0Centros de Acopio. De encontrarse que se est\u00e1 almacenando y distribuyendo \u00a0combustibles l\u00edquidos derivados del petr\u00f3leo por sitios no aprobados por la \u00a0autoridad competente, tendr\u00e1 la obligaci\u00f3n de informar de inmediato a la fuerza \u00a0p\u00fablica o las autoridades que ejerzan funciones de polic\u00eda judicial, para que \u00a0procedan de conformidad con el Par\u00e1grafo Segundo del art\u00edculo Primero del \u00a0presente decreto. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 6\u00b0. La Planta de Abastecimiento, el Centro de Acopio, el Punto de \u00a0Recolecci\u00f3n y el Transportador, que infrinjan el presente decreto, y las dem\u00e1s \u00a0normas sobre el funcionamiento del servicio p\u00fablico de distribuci\u00f3n, transporte \u00a0y almacenamiento de combust\u00fcbles l\u00edquidos derivados del petr\u00f3leo, estar\u00e1n \u00a0sujetos a la imposici\u00f3n por parte del Ministerio de Minas y Energ\u00eda de las \u00a0siguientes sanciones, de conformidad con la naturaleza, efectos, modalidades y \u00a0gravedad del hecho: Amonestaci\u00f3n, Multa, Suspensi\u00f3n del Servicio y Cancelaci\u00f3n \u00a0de la Autorizaci\u00f3n, de acuerdo con lo establecido con el Decreto 283 de 1990 \u00a0o aquellas normas que lo modifique, adicione o derogue. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 7\u00b0. La fuerza p\u00fablica y las autoridades de control se\u00f1aladas por \u00a0la ley, podr\u00e1n solicitar al Transportador, la copia de la Gu\u00eda \u00fanica de \u00a0Transporte de Combustible que ampara el traslado de los combustibles l\u00edquidos \u00a0derivados del petr\u00f3leo, desde la Planta de Abastecimiento o el Centro de Acopio \u00a0hasta las Estaciones de Servicio o establecimiento de los Grandes Consumidores \u00a0de los municipios calificados como Zona de Frontera en el Departamento de \u00a0Arauca, as\u00ed como la respectiva Declaraci\u00f3n de importaci\u00f3n. En el evento en que \u00a0no se porte, deber\u00e1n inmovilizar los veh\u00edculos y ponerlos a disposici\u00f3n de las \u00a0autoridades competentes, sin perjuicio de las acciones que procedan respecto de \u00a0la mercanc\u00eda conforme con las disposiciones especiales y de las dem\u00e1s sanciones \u00a0a que haya lugar. \u00a0 \u00a0<\/p>\n<p>Texto inicial: \u201cAprobaci\u00f3n \u00a0de centros de acopio como terceros. De conformidad con lo dispuesto en el inciso \u00a02\u00b0 del art\u00edculo 19 de la Ley 191 de 1995, modificado por el art\u00edculo 1\u00b0 \u00a0de la Ley 681 de 2001, el Ministerio de Minas y \u00a0Energ\u00eda podr\u00e1 aprobar e inscribir como terceros a los Centros de Acopio \u00a0ubicados en el Departamento de Arauca que, adem\u00e1s de cumplir con lo se\u00f1alado en \u00a0el art\u00edculo sexto del Decreto 2195 de 2001, cumplan los siguientes \u00a0requisitos: \u00a0 \u00a0<\/p>\n<p>1. Localizaci\u00f3n en sitios aleda\u00f1os al cruce de frontera, habilitados \u00a0por la DIAN como Dep\u00f3sitos, conforme con las disposiciones establecidas en el \u00a0T\u00edtulo III, Cap\u00edtulo II, art\u00edculos 47 y siguientes del Decreto 2685 de 1999 \u00a0y dem\u00e1s normas \u00a0que lo adicionen, modifiquen o aclaren, salvo lo previsto en el literal a) del \u00a0art\u00edculo 51 y en el literal b) del art\u00edculo 71 respecto al valor del patrimonio \u00a0neto a acreditar, el cual para efectos de la habilitaci\u00f3n de Centros de Acopio \u00a0como Dep\u00f3sitos ser\u00e1 de una d\u00e9cima parte del valor consignado en las referidas \u00a0disposiciones. \u00a0 \u00a0<\/p>\n<p>2. La distancia de los linderos del Centro de Acopio a los linderos m\u00e1s \u00a0pr\u00f3ximos de sitios de alta densidad poblacional, tales como templos, escuelas, \u00a0colegios, hospitales, cl\u00ednicas, supermercados, centros comerciales, teatros, \u00a0polideportivos, bibliotecas p\u00fablicas, clubes sociales, edificios multifamiliares \u00a0y establecimientos similares, no podr\u00e1 ser inferior a cien (100) metros. \u00a0 \u00a0<\/p>\n<p>3. La distribuci\u00f3n de los tanques y dem\u00e1s instalaciones y su separaci\u00f3n \u00a0con respecto a propiedades adyacentes deber\u00e1 cumplir con las distancias m\u00ednimas \u00a0indicadas en las Tablas 1 y 2 del art\u00edculo 3\u00b0 del Decreto 318 de 2003 \u00a0o las normas que \u00a0lo modifiquen, adicionen o deroguen. \u00a0 \u00a0<\/p>\n<p>4. Los muros o paredes de las oficinas deber\u00e1n ser construidos con \u00a0materiales resistentes a la combusti\u00f3n. \u00a0 \u00a0<\/p>\n<p>5. Todo tanque o grupo de tanques que contenga combustibles deber\u00e1 \u00a0estar rodeado por un muro de retenci\u00f3n impermeabilizado, que deber\u00e1 construirse \u00a0en concreto, tierra apisonada e impermeabilizada u otro material adecuado. La \u00a0altura m\u00ednima de dicho muro ser\u00e1 de sesenta cent\u00edmetros (60 cm) y la m\u00e1xima \u00a0ser\u00e1 de dos metros (2 m). Si un recinto rodeado por un muro de retenci\u00f3n \u00a0contiene un solo tanque, su capacidad neta ser\u00e1 por lo menos igual a la \u00a0capacidad del tanque y se calcular\u00e1 como si tal tanque no existiera. Esto \u00a0\u00faltimo teniendo en cuenta que, en caso de m\u00e1ximo derrame del tanque, quedar\u00e1 en \u00a0este un nivel l\u00edquido igual a la altura del muro de retenci\u00f3n. Si el recinto de \u00a0retenci\u00f3n contiene dos o m\u00e1s tanques, su capacidad neta ser\u00e1 por lo menos igual \u00a0a la del tanque de mayor capacidad dentro del recinto m\u00e1s el diez por ciento \u00a0(10%) de la capacidad de los otros tanques. \u00a0 \u00a0<\/p>\n<p>6. En el interior de los muros de contenci\u00f3n no debe haber ning\u00fan tipo \u00a0de instalaciones diferentes de las estrictamente necesarias para el manejo \u00a0seguro de los combustibles l\u00edquidos derivados del petr\u00f3leo. \u00a0 \u00a0<\/p>\n<p>7. Todas las tuber\u00edas y accesorios, dentro y fuera de los recintos o \u00a0muros de retenci\u00f3n, ser\u00e1n de acero-carb\u00f3n. Las que se instalen dentro deber\u00e1n \u00a0dise\u00f1arse para resistir altas temperaturas. \u00a0 \u00a0<\/p>\n<p>8. Las instalaciones de carga de carrotanques deben estar separadas de \u00a0tanques sobre superficie, dep\u00f3sitos y otras edificaciones del dep\u00f3sito o el \u00a0lindero m\u00e1s cercano de la propiedad vecina sobre la cual puede construirse por \u00a0una distancia de, por lo menos, cuatro metros con sesenta cent\u00edmetros (4.6 m), \u00a0medida desde la boca de llenado o desde la conexi\u00f3n para transferencia de \u00a0l\u00edquido o vapor m\u00e1s cercana. \u00a0 \u00a0<\/p>\n<p>9. Toda plataforma de llenadero deber\u00e1 estar provista, al menos, de: \u00a0 \u00a0<\/p>\n<p>a) Dos escaleras, con inclinaci\u00f3n m\u00e1xima de cuarenta y cinco grados \u00a0(45\u00b0); \u00a0 \u00a0<\/p>\n<p>b) Conexiones a tierra para eliminar la corriente est\u00e1tica, una por \u00a0cada brazo de llenado; \u00a0 \u00a0<\/p>\n<p>c) Se\u00f1ales preventivas en colores reflectivos; \u00a0 \u00a0<\/p>\n<p>10. Los equipos contra incendio que deber\u00e1n ser instalados contar\u00e1n \u00a0como m\u00ednimo con: \u00a0 \u00a0<\/p>\n<p>a) Tanque para agua contra incendio, con un m\u00ednimo de cuatro (4) horas \u00a0de almacenamiento; \u00a0 \u00a0<\/p>\n<p>b) Sistema de hidrantes, monitores o regaderas exteriores para enfriamiento; \u00a0 \u00a0<\/p>\n<p>c) El n\u00famero de extintores port\u00e1tiles suficientes para atender un \u00a0conato de incendio en las diferentes \u00e1reas de la instalaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>11. Plan de emergencia para casos de derrames, fugas o incendio. \u00a0 \u00a0<\/p>\n<p>12. Constituir P\u00f3liza de Responsabilidad Civil Extracontractual por un \u00a0valor asegurado igual al previsto en el literal a) del art\u00edculo 39 del Decreto 1521 de 1998 \u00a0para Plantas de \u00a0Abastecimiento. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. No obstante lo establecido en el art\u00edculo 7\u00b0 del presente \u00a0decreto y con el fin de mantener el orden de prelaci\u00f3n se\u00f1alado en el art\u00edculo \u00a02\u00b0 del Decreto 2195 de 2001, \u00a0si existen \u00a0plantas de abastecimiento para almacenamiento y distribuci\u00f3n de combustibles \u00a0l\u00edquidos derivados del petr\u00f3leo (gasolina sin plomo y ACPM) el Ministerio de \u00a0Minas y Energ\u00eda se abstendr\u00e1 de aprobar e inscribir como terceros a nuevos \u00a0centros de acopio y las autorizaciones a la fecha otorgadas perder\u00e1n su validez \u00a0en un per\u00edodo de seis (6) meses, tiempo durante el cual podr\u00e1n habilitarse como \u00a0plantas de abastecimiento, cumpliendo para el efecto los requisitos exigidos en \u00a0el Decreto 283 de 1990, \u00a0o las normas que \u00a0lo modifiquen, adicionen o deroguen.\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00ba. Actividades de distribuci\u00f3n. Sin perjuicio de lo \u00a0se\u00f1alado en el art\u00edculo 2\u00b0 del Decreto 2195 de 2001, \u00a0la planta de abastecimiento ubicada en el municipio de Arauca y\/o los Centros \u00a0de Acopio aprobados, registrados y habilitados de acuerdo con lo previsto en el \u00a0art\u00edculo anterior solo podr\u00e1n distribuir combustibles importados de Venezuela a \u00a0las estaciones de servicio legalmente establecidas, con cupo asignado por la \u00a0UPME y a Ecopetrol S.A., siempre que los mismos se destinen a los municipios \u00a0calificados como Zonas de Frontera en el Departamento de Arauca. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Derogado por el Decreto 2363 de 2006, \u00a0art\u00edculo 3\u00ba. Una vez se complete en la planta de \u00a0abastecimiento y\/o en los Centros de Acopio el volumen m\u00e1ximo de combustibles \u00a0asignado por la UPME para los municipios de Zona de Frontera del Departamento \u00a0de Arauca, la cantidad que exceda al mismo podr\u00e1 ser distribuida al resto del \u00a0territorio aduanero nacional o al exterior, previa modificaci\u00f3n a la \u00a0declaraci\u00f3n de importaci\u00f3n, conforme con lo establecido en el Decreto 2685 de 1999 \u00a0y dem\u00e1s normas que lo modifiquen, adicionen o \u00a0aclaren. En este sentido, respecto del excedente de combustibles se deber\u00e1n \u00a0pagar los tributos aduaneros, sobretasa y dem\u00e1s impuestos exigidos por la ley. \u00a0As\u00ed mismo, deber\u00e1 cumplirse con las dem\u00e1s normas de importaci\u00f3n, \u00a0almacenamiento, transporte, marcaci\u00f3n y calidad de los combustibles. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 4\u00ba. Visto bueno del Ministerio de Minas y Energ\u00eda. Para el \u00a0otorgamiento del visto bueno de que trata el art\u00edculo 1\u00b0 de la Ley 681 \u00a0del 9 de agosto de 2001, Ecopetrol S.A. presentar\u00e1 ante el Ministerio de \u00a0Minas y Energ\u00eda, dentro de los cinco (5) d\u00edas siguientes a la publicaci\u00f3n de \u00a0este Decreto, un plan de abastecimiento de combustibles l\u00edquidos derivados del \u00a0petr\u00f3leo para cada uno de los municipios considerados como Zonas de Frontera en \u00a0el Departamento de Arauca, en los t\u00e9rminos se\u00f1alados en el presente Decreto; \u00a0plan que deber\u00e1 consultar los cupos m\u00e1ximos de combustibles fijados para cada \u00a0municipio por la Unidad de Planeaci\u00f3n Minero Energ\u00e9tica, UPME. \u00a0 \u00a0<\/p>\n<p>Dentro de los cinco (5) d\u00edas siguientes a la fecha de presentaci\u00f3n del \u00a0referido Plan, el Ministerio de Minas y Energ\u00eda-Direcci\u00f3n de Hidrocarburos lo evaluar\u00e1 \u00a0y, si es el caso, solicitar\u00e1 a Ecopetrol S.A. realizar los ajustes pertinentes. \u00a0En este evento, Ecopetrol S.A. deber\u00e1 presentar ante la misma Entidad, dentro \u00a0del plazo que esta le estipule, las modificaciones respectivas. Una vez \u00a0conforme con el plan, el Ministerio de Minas y Energ\u00eda-Direcci\u00f3n de \u00a0Hidrocarburos lo aprobar\u00e1 mediante resoluci\u00f3n motivada y otorgar\u00e1 en ese mismo \u00a0acto los vistos buenos para la distribuci\u00f3n de combustibles en los municipios y \u00a0corregimientos de Zona de Frontera. \u00a0 \u00a0<\/p>\n<p>El visto bueno para la distribuci\u00f3n de combustibles en el Departamento de \u00a0Arauca estar\u00e1 vigente por doce (12) meses; al final de dicho per\u00edodo, si es \u00a0necesario, se deber\u00e1 ajustar el plan de abastecimiento a las condiciones del \u00a0mercado e informarlo al Ministerio de Minas y Energ\u00eda para su aprobaci\u00f3n, en \u00a0los t\u00e9rminos se\u00f1alados en el presente decreto. De lo contrario, permanecer\u00e1 \u00a0vigente por un per\u00edodo de hasta dos (2) a\u00f1os m\u00e1s, con revisiones anuales en los \u00a0t\u00e9rminos indicados en este inciso. \u00a0 \u00a0<\/p>\n<p>Una vez otorgado el visto bueno por parte del Ministerio de Minas y \u00a0Energ\u00eda, Ecopetrol S.A. iniciar\u00e1 los tr\u00e1mites correspondientes para el \u00a0cumplimiento de la funci\u00f3n de distribuci\u00f3n en los municipios y corregimientos \u00a0considerados como Zona de Frontera en el Departamento de Arauca. \u00a0 \u00a0<\/p>\n<p>Dentro de los tres (3) d\u00edas siguientes a la ejecutoria de los actos \u00a0administrativos que conceden el visto bueno de que trata el presente Art\u00edculo, \u00a0Ecopetrol S.A. deber\u00e1 poner en conocimiento de la Direcci\u00f3n de Impuestos y \u00a0Aduanas Nacionales, DIAN, y dem\u00e1s autoridades de control competentes el plan de \u00a0abastecimiento de combustibles l\u00edquidos derivados del petr\u00f3leo para cada una de \u00a0las Zonas de Frontera y sus correspondientes modificaciones. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 5\u00ba. Modificado por el Decreto 4237 de 2004, \u00a0art\u00edculo 3\u00ba. Importaci\u00f3n de combustible. La importaci\u00f3n de \u00a0combustibles l\u00edquidos derivados del petr\u00f3leo de que trata este decreto, se \u00a0realizar\u00e1 bajo la modalidad de franquicia, conforme con las disposiciones del Decreto 2685 de 1999 \u00a0y dem\u00e1s normas que lo modifiquen, aclaren o deroguen, salvo lo relacionado en \u00a0el Cap\u00edtulo II, T\u00edtulo V, art\u00edculos 90 y siguientes. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. La Planta de Abastecimiento y el Centro de Acopio, verificar\u00e1n \u00a0que los combustibles l\u00edquidos derivados del petr\u00f3leo, que ingresen al dep\u00f3sito \u00a0correspondan con la informaci\u00f3n consignada en la gu\u00eda de compra. \u00a0 \u00a0<\/p>\n<p>La Gu\u00eda de Compra har\u00e1 las veces de factura comercial y no se exigir\u00e1 el \u00a0documento de transporte como soporte de la declaraci\u00f3n de importaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Texto inicial: \u201cImportaci\u00f3n de \u00a0combustibles. El tr\u00e1mite para la importaci\u00f3n de combustibles l\u00edquidos derivados \u00a0del petr\u00f3leo de que trata este decreto se sujetar\u00e1 a las disposiciones del Decreto 2685 de 1999, \u00a0salvo lo \u00a0relacionado en el Cap\u00edtulo II, T\u00edtulo V, art\u00edculo 90 y siguientes. \u00a0 \u00a0<\/p>\n<p>La Direcci\u00f3n de Impuestos y Aduanas Nacionales, DIAN, habilitar\u00e1, \u00a0mediante resoluci\u00f3n motivada, los sitios para el ingreso de los referidos \u00a0combustibles.\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 6\u00ba. Responsabilidades y obligaciones de los terceros, \u00a0distribuidores mayoristas y minoristas. Los terceros, distribuidores mayoristas \u00a0y minoristas de combustibles l\u00edquidos derivados del petr\u00f3leo en los municipios \u00a0calificados como Zona de Frontera del Departamento de Arauca, deber\u00e1n tener en \u00a0cuenta lo siguiente: \u00a0 \u00a0<\/p>\n<p>1. Los combustibles l\u00edquidos derivados del petr\u00f3leo que se importen al \u00a0amparo de este Decreto no podr\u00e1n ser comercializados y\/o distribuidos a trav\u00e9s \u00a0de estaciones de servicio en vol\u00famenes superiores a los determinados por la \u00a0Unidad de Planeaci\u00f3n Minero Energ\u00e9tica, UPME, y\/o transportados por personas \u00a0naturales o jur\u00eddicas que no se encuentren autorizadas o no tengan sus \u00a0veh\u00edculos debidamente registrados ante el Ministerio de Minas y Energ\u00eda. Para \u00a0el efecto, el Ministerio de Minas y Energ\u00eda y Ecopetrol S.A. adelantar\u00e1n las \u00a0acciones de control que consideren pertinentes, sin perjuicio de las facultades \u00a0legales otorgadas a la Direcci\u00f3n de Impuestos y Aduanas Nacionales, DIAN. \u00a0 \u00a0<\/p>\n<p>2. La planta de abastecimiento establecida en el municipio de Arauca, \u00a0Departamento de Arauca, que abastezca las estaciones de servicio y\/o los grandes \u00a0consumidores ubicados en los municipios y corregimientos fronterizos del \u00a0departamento de Arauca deber\u00e1 llevar un registro independiente para cada uno de \u00a0los combustibles que se distribuyan all\u00ed, el cual contendr\u00e1 entre otros: nombre \u00a0de la estaci\u00f3n de servicio, transportador, municipio, volumen retirado mensual, \u00a0valor correspondiente a sobretasa. Este registro deber\u00e1 ser informado \u00a0mensualmente a la UPME, con copia a la DIAN y a Ecopetrol S.A., dentro de los \u00a0cinco (5) d\u00edas siguientes a la terminaci\u00f3n del mes, so pena de hacerse acreedor \u00a0a la imposici\u00f3n de las sanciones contempladas en el Decreto 283 de 1990 \u00a0o las normas que lo modifiquen, aclaren, adicionen o deroguen. \u00a0 \u00a0<\/p>\n<p>3. Los Centros de Acopio deber\u00e1n enviarle mensualmente a Ecopetrol S.A., \u00a0con copia a la UPME y a la DIAN, a m\u00e1s tardar el quinto (5\u00b0) d\u00eda del mes \u00a0siguiente al de la adquisici\u00f3n del producto, la informaci\u00f3n sobre compras y \u00a0ventas a cada una de las estaciones de servicio de los municipios donde operan, \u00a0a los grandes consumidores y\/o a Ecopetrol S.A. debidamente certificadas por \u00a0Contador P\u00fablico o Revisor Fiscal, seg\u00fan corresponda. Igualmente, deber\u00e1n \u00a0enviar un balance de inventarios de su respectiva operaci\u00f3n y remitir un \u00a0informe detallado de la sobretasa recaudada y pagada. \u00a0 \u00a0<\/p>\n<p>4. Las estaciones de servicio que distribuyan combustibles en los \u00a0municipios y corregimientos ubicados en Zonas de Frontera del Departamento de Arauca \u00a0deber\u00e1n dentro de los cinco (5) d\u00edas siguientes a la terminaci\u00f3n del mes, \u00a0informar a la UPME con copia a Ecopetrol S.A. y a la DIAN, el volumen-expresado \u00a0en galones-de combustibles adquiridos y la relaci\u00f3n de las ventas efectuadas en \u00a0el mes calendario inmediatamente anterior, discriminando productos y precios de \u00a0los mismos, so pena de hacerse acreedoras a las sanciones se\u00f1aladas en el Decreto 1521 de 1998 \u00a0o las normas que lo modifiquen, aclaren, adicionen o deroguen. \u00a0 \u00a0<\/p>\n<p>5. Los grandes consumidores de combustibles ubicados en los municipios y \u00a0corregimientos fronterizos del Departamento de Arauca deber\u00e1n informar a la \u00a0UPME, con copia a Ecopetrol S.A. y a la DIAN, dentro de los cinco (5) d\u00edas \u00a0siguientes a la terminaci\u00f3n del mes, el volumen-expresado en galones-de \u00a0combustibles adquiridos, so pena de hacerse acreedores a las sanciones \u00a0se\u00f1aladas en la ley. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 7\u00ba. En los aspectos no contemplados en el presente decreto se dar\u00e1 \u00a0aplicaci\u00f3n a las normas contenidas en el Decreto 2195 de 2001 \u00a0o las normas que lo modifiquen, adicionen o deroguen. En este sentido, si no se \u00a0tienen las condiciones para la importaci\u00f3n de combustibles provenientes de la \u00a0Rep\u00fablica Bolivariana de Venezuela, se aplicar\u00e1 el plan de abastecimiento con \u00a0producto nacional que para el efecto haya dise\u00f1ado Ecopetrol S.A., con el \u00a0respectivo visto bueno del Ministerio de Minas y Energ\u00eda. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 8\u00ba. El presente decreto rige a partir de la fecha de su \u00a0publicaci\u00f3n y deroga las disposiciones que le sean contrarias. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 23 de julio de 2004. \u00a0 \u00a0<\/p>\n<p>\u00c1LVARO URIBE V\u00c9LEZ \u00a0 \u00a0<\/p>\n<p>El Ministro del Interior y de Justicia, \u00a0 \u00a0<\/p>\n<p>Sabas Pretelt de \u00a0la Vega. \u00a0 \u00a0<\/p>\n<p>El Ministro de Hacienda y Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Alberto \u00a0Carrasquilla Barrera. \u00a0 \u00a0<\/p>\n<p>El Viceministro de Minas y Energ\u00eda, encargado de las funciones del Despacho \u00a0del Ministro de Minas y Energ\u00eda, \u00a0 \u00a0<\/p>\n<p>Manuel Maiguashca \u00a0Olano. \u00a0 \u00a0<\/p>\n<p>El Ministro de Comercio, Industria y Turismo, \u00a0 \u00a0<\/p>\n<p>Jorge Humberto \u00a0Botero. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 2337 DE 2004 \u00a0 \u00a0 (julio 23) \u00a0 \u00a0 por el \u00a0cual se reglamenta la importaci\u00f3n, almacenamiento y distribuci\u00f3n de \u00a0combustibles provenientes de la Rep\u00fablica Bolivariana de Venezuela en las Zonas \u00a0de Frontera del Departamento de Arauca. \u00a0 \u00a0 Nota 1: Ver Decreto 1073 de 2015, \u00a0Decreto \u00danico Reglamentario \u00a0del Sector Administrativo de Minas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-35721","post","type-post","status-publish","format-standard","hentry","category-decretos-2004"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/35721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=35721"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/35721\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=35721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=35721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=35721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}