{"id":35860,"date":"2023-07-26T20:30:45","date_gmt":"2023-07-26T20:30:45","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-3059-de-2004\/"},"modified":"2023-07-26T20:30:45","modified_gmt":"2023-07-26T20:30:45","slug":"decreto-3059-de-2004","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-3059-de-2004\/","title":{"rendered":"DECRETO 3059 DE 2004"},"content":{"rendered":"\n<p>DECRETO 3059 DE 2004 \u00a0 \u00a0<\/p>\n<p>(septiembre 20) \u00a0 \u00a0<\/p>\n<p>por el cual se designa el Revisor Fiscal del Banco Agrario \u00a0de Colombia S.A. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, en ejercicio de \u00a0sus facultades constitucionales y legales, en especial las que le confiere el numeral \u00a02 del art\u00edculo 79 del Estatuto Org\u00e1nico del Sistema Financiero, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Des\u00edgnase a Deloitte &amp; Touche Ltda., como \u00a0la firma que ejercer\u00e1 la Revisor\u00eda Fiscal del Banco Agrario de Colombia S.A., \u00a0hasta el 15 de abril de 2005. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. El presente decreto rige a partir de la fecha \u00a0de su publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 20 de septiembre de 2004. \u00a0 \u00a0<\/p>\n<p>\u00c1LVARO URIBE V\u00c9LEZ \u00a0 \u00a0<\/p>\n<p>El Ministro de Hacienda y Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Alberto Carrasquilla Barrera \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 3059 DE 2004 \u00a0 \u00a0 (septiembre 20) \u00a0 \u00a0 por el cual se designa el Revisor Fiscal del Banco Agrario \u00a0de Colombia S.A. \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, en ejercicio de \u00a0sus facultades constitucionales y legales, en especial las que le confiere el numeral \u00a02 del art\u00edculo 79 del Estatuto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-35860","post","type-post","status-publish","format-standard","hentry","category-decretos-2004"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/35860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=35860"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/35860\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=35860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=35860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=35860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}