{"id":36149,"date":"2023-07-26T20:31:01","date_gmt":"2023-07-26T20:31:01","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-4339-de-2004\/"},"modified":"2023-07-26T20:31:01","modified_gmt":"2023-07-26T20:31:01","slug":"decreto-4339-de-2004","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-4339-de-2004\/","title":{"rendered":"DECRETO 4339 DE 2004"},"content":{"rendered":"\n<p>DECRETO 4339 DE2004 \u00a0 \u00a0<\/p>\n<p>(diciembre22) \u00a0 \u00a0<\/p>\n<p>por el \u00a0cual se fija un gravamen arancelario a las importaciones de cigarrillos de \u00a0tabaco rubio, procedentes y originarias de Venezuela. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de \u00a0Colombia, en ejercicio de sus facultades constitucionales y legales, en \u00a0especial de las que le confiere el numeral 25 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica, \u00a0con sujeci\u00f3n a las normas generales previstas en las Leyes 6\u00aa de 1971 y 7\u00aa de 1991 y previo \u00a0concepto del Comit\u00e9 de Asuntos Aduaneros Arancelarios y de Comercio Exterior, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que de conformidad con el \u00a0art\u00edculo 16 del Decreto \u00a0242 del 23 de agosto de 1979, Reforma Parcial del Reglamento de la Ley de \u00a0Impuesto sobre Cigarrillos y Manufacturas de Tabaco, Venezuela establece que \u00a0&#8220;las especies importadas no podr\u00e1n ser ofrecidas al consumo a un precio de \u00a0venta igual o menor de los establecidos para los cigarrillos, tabacos y \u00a0picaduras de producci\u00f3n nacional&#8221;; \u00a0 \u00a0<\/p>\n<p>Que el Tribunal de Justicia de \u00a0la Comunidad Andina,(CAN), mediante auto del 19 de mayo de 2004, declar\u00f3 a la \u00a0Rep\u00fablica Bolivariana de Venezuela en desacato de la sentencia proferida el 27 \u00a0de agosto de 2003, dentro de la acci\u00f3n de incumplimiento instaurada por la \u00a0Secretar\u00eda General de la Comunidad Andina, por violaci\u00f3n del principio de Trato \u00a0Nacional a los cigarrillos, tabacos y picaduras importados de los Pa\u00edses \u00a0Miembros, dentro del proceso 52-Al-2002; \u00a0 \u00a0<\/p>\n<p>Que mediante auto del 4 de \u00a0agosto de 2004, el Tribunal de Justicia de la CAN determin\u00f3 los l\u00edmites \u00a0mediante los cuales los Pa\u00edses Miembros pueden restringir o suspender las \u00a0ventajas del Acuerdo de Cartagena a la Rep\u00fablica de Venezuela, siendo \u00a0obligatorio imponer un gravamen del ocho al doce por ciento (8 al 12%)sobre el \u00a0valor de las importaciones de cigarrillos de tabaco rubio clasificados en la \u00a0subpartida NANDINA 2402.20.20, procedentes y originarios del citado pa\u00eds; \u00a0 \u00a0<\/p>\n<p>Que Colombia debe informar a la \u00a0Secretar\u00eda General de la CAN sobre las medidas adoptadas para la aplicaci\u00f3n de \u00a0las sanciones vigentes desde el 25 de agosto de2004, fecha de publicaci\u00f3n del \u00a0auto del Tribunal en la Gaceta Oficial del Acuerdo de Cartagena; \u00a0 \u00a0<\/p>\n<p>Que el Comit\u00e9 de Asuntos \u00a0Aduaneros, Arancelarios y de Comercio Exterior en la Sesi\u00f3n133 del 25 de \u00a0noviembre de 2004, recomend\u00f3 adoptar el gravamen arancelario del doce por \u00a0ciento (12%) sobre el valor de las importaciones de cigarrillos de tabaco rubio \u00a0procedentes y originarios de Venezuela, con el fin de dar cumplimiento a lo \u00a0ordenado por el Tribunal de Justicia de la CAN, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo1\u00b0. Los cigarrillos de \u00a0tabaco rubio clasificados en la subpartida NANDINA 2402.20.20.00, procedentes y \u00a0originarios de Venezuela, ingresar\u00e1n al territorio aduanero colombiano con un \u00a0gravamen arancelario de 12%. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo2\u00b0. Lo establecido en el \u00a0art\u00edculo 1\u00b0 del presente decreto, no se aplicar\u00e1 a las mercanc\u00edas que hayan \u00a0sido embarcadas con anterioridad a la fecha de entrada en vigencia del presente \u00a0decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo3\u00b0. El presente decreto \u00a0rige a partir de la fecha de su publicaci\u00f3n en el Diario Oficial y \u00a0estar\u00e1 vigente hasta tanto el Tribunal de Justicia de la Comunidad Andina \u00a0determine que Venezuela ha dado estricto cumplimiento a la sentencia del 27 de \u00a0agosto de 2003, proferida dentro del proceso 52-Al-2002. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C, a 22 de diciembre de 2004. \u00a0 \u00a0<\/p>\n<p>\u00c1LVARO \u00a0URIBEV\u00c9LEZ \u00a0 \u00a0<\/p>\n<p>El Ministro de Hacienda y Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Alberto \u00a0Carrasquilla Barrera. \u00a0 \u00a0<\/p>\n<p>El Ministro de Agricultura y Desarrollo Rural \u00a0 \u00a0<\/p>\n<p>Carlos \u00a0Gustavo Cano. \u00a0 \u00a0<\/p>\n<p>El Ministro de Comercio, Industria y Turismo, \u00a0 \u00a0<\/p>\n<p>Jorge \u00a0Humberto Botero. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 4339 DE2004 \u00a0 \u00a0 (diciembre22) \u00a0 \u00a0 por el \u00a0cual se fija un gravamen arancelario a las importaciones de cigarrillos de \u00a0tabaco rubio, procedentes y originarias de Venezuela. \u00a0 \u00a0 El Presidente de la Rep\u00fablica de \u00a0Colombia, en ejercicio de sus facultades constitucionales y legales, en \u00a0especial de las que le confiere el numeral [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-36149","post","type-post","status-publish","format-standard","hentry","category-decretos-2004"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/36149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=36149"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/36149\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=36149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=36149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=36149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}