{"id":36283,"date":"2023-07-26T20:31:09","date_gmt":"2023-07-26T20:31:09","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-919-de-2004\/"},"modified":"2023-07-26T20:31:09","modified_gmt":"2023-07-26T20:31:09","slug":"decreto-919-de-2004","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/26\/decreto-919-de-2004\/","title":{"rendered":"DECRETO 919 DE 2004"},"content":{"rendered":"\n<p>DECRETO 919 DE 2004 \u00a0 \u00a0<\/p>\n<p>(marzo 26) \u00a0 \u00a0<\/p>\n<p>por el cual se reglamentan las donaciones internacionales de \u00a0medicamentos y dispositivos m\u00e9dicos. \u00a0 \u00a0<\/p>\n<p>Nota 1: Derogado por el Decreto 218 de 2019, \u00a0art\u00edculo 15. \u00a0 \u00a0<\/p>\n<p>Nota 2: Ver Decreto 2475 de 2018. \u00a0Ver Decreto 780 de 2016, \u00a0art\u00edculo 4.1.3, excluy\u00f3 de la derogatoria integral este decreto. Decreto \u00a0\u00danico Reglamentario del Sector Salud y Protecci\u00f3n Social. \u00a0 \u00a0<\/p>\n<p>El Presidente de la \u00a0Rep\u00fablica de Colombia, en ejercicio de sus facultades constitucionales y \u00a0legales y en especial las conferidas por el numeral 11 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica y \u00a0en el art\u00edculo 245 de la Ley 100 de 1993, \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que las donaciones de \u00a0medicamentos y dispositivos m\u00e9dicos deben constituir un beneficio real para su \u00a0receptor, garantizando efectividad, calidad y seguridad; \u00a0 \u00a0<\/p>\n<p>Que las donaciones \u00a0internacionales de medicamentos y dispositivos m\u00e9dicos deben cumplir con las \u00a0disposiciones sanitarias vigentes del pa\u00eds receptor y ajustarse a sus \u00a0necesidades; \u00a0 \u00a0<\/p>\n<p>Que el Gobierno Nacional \u00a0debe asegurar el cumplimiento de los est\u00e1ndares t\u00e9cnicos de seguridad, eficacia \u00a0y calidad de los medicamentos y dispositivos m\u00e9dicos, que se reciban en \u00a0donaci\u00f3n; \u00a0 \u00a0<\/p>\n<p>Que en m\u00e9rito de lo \u00a0expuesto, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Ambito de aplicaci\u00f3n. Las disposiciones \u00a0contenidas en el presente decreto regulan los procesos, requisitos y dem\u00e1s aspectos \u00a0relacionados con las donaciones internacionales con fines sociales y \u00a0humanitarios de medicamentos y dispositivos m\u00e9dicos dentro de los cuales no se \u00a0incluyen los equipos biom\u00e9dicos. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. Definiciones. \u00a0Para los efectos previstos en el presente decreto se adoptar\u00e1n las siguientes \u00a0definiciones: \u00a0 \u00a0<\/p>\n<p>Donante. \u00a0Se consideran donantes los movimientos \u00a0internacionales, empresas privadas, las personas naturales y\/o jur\u00eddicas, las \u00a0organizaciones no gubernamentales, gobiernos, fabricantes y distribuidores de \u00a0medicamentos y dispositivos m\u00e9dicos, que voluntariamente ofrecen medicamentos y \u00a0dispositivos m\u00e9dicos con fines humanitarios. \u00a0 \u00a0<\/p>\n<p>Receptor. \u00a0Es la entidad p\u00fablica o privada que recibe \u00a0una donaci\u00f3n y se constituye en el responsable nacional de la misma. \u00a0 \u00a0<\/p>\n<p>Vida \u00a0\u00fatil. Es el intervalo de tiempo \u00a0durante el cual se espera que un medicamento o un dispositivo m\u00e9dico, en \u00a0condiciones de almacenamiento correctas, satisfaga las especificaciones de \u00a0calidad establecidas. Se emplea para establecer su fecha de expiraci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0. Requisitos \u00a0y procedimiento para la autorizaci\u00f3n de las donaciones. Los medicamentos y \u00a0dispositivos m\u00e9dicos que ingresen al pa\u00eds mediante donaci\u00f3n, no requerir\u00e1n \u00a0registro sanitario. No obstante deber\u00e1n cumplir con los siguientes requisitos: \u00a0 \u00a0<\/p>\n<p>1. Los principios activos \u00a0de los medicamentos donados deber\u00e1n estar incluidos en las normas \u00a0farmacol\u00f3gicas o en actas de la Comisi\u00f3n Revisora del Invima \u00a0y su utilizaci\u00f3n deber\u00e1 sujetarse a las indicaciones all\u00ed establecidas. \u00a0 \u00a0<\/p>\n<p>2. Los medicamentos y \u00a0dispositivos m\u00e9dicos deber\u00e1n cumplir con los par\u00e1metros de c alidad se\u00f1alados en las normas nacionales e internacionales \u00a0vigentes y en el momento de su ingreso al pa\u00eds deber\u00e1n tener como m\u00ednimo cuatro \u00a0(4) meses de vida \u00fatil y no podr\u00e1n encontrarse en etapa de experimentaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>3. Las condiciones de \u00a0almacenamiento y conservaci\u00f3n deber\u00e1n garantizar la estabilidad del producto, \u00a0incluyendo cadena de fr\u00edo cuando esta se requiera. \u00a0 \u00a0<\/p>\n<p>4. Los envases, empaques \u00a0y r\u00f3tulos deben cumplir con las especificaciones propias de cada medicamento o \u00a0dispositivo m\u00e9dico, garantizando as\u00ed su estabilidad y calidad. \u00a0 \u00a0<\/p>\n<p>5. Los medicamentos y \u00a0dispositivos m\u00e9dicos donados podr\u00e1n ingresar al pa\u00eds con el etiquetado aprobado \u00a0en el pa\u00eds de origen y su embalaje debe ser adecuado, teniendo en cuenta como \u00a0m\u00ednimo: \u00a0 \u00a0<\/p>\n<p>a) Utilizaci\u00f3n de \u00a0material apropiado para facilitar su manipulaci\u00f3n, transporte y almacenamiento \u00a0adecuado para prevenir da\u00f1os; \u00a0 \u00a0<\/p>\n<p>b) Encontrarse sellado y \u00a0sin indicios de haber sido abierto o sometido a condiciones de humedad y\/o temperatura \u00a0que represente deformaci\u00f3n o deterioro de su contenido; \u00a0 \u00a0<\/p>\n<p>c) Apropiada \u00a0identificaci\u00f3n donde se indique el contenido; \u00a0 \u00a0<\/p>\n<p>d) No debe contener \u00a0art\u00edculos diferentes a los del listado. \u00a0 \u00a0<\/p>\n<p>6. Documento de \u00a0ofrecimiento de la donaci\u00f3n o de aceptaci\u00f3n de la misma por el receptor. \u00a0 \u00a0<\/p>\n<p>7. Copia del certificado \u00a0expedido por la autoridad sanitaria competente del pa\u00eds de origen, en donde se \u00a0indique que el producto ha sido autorizado para su utilizaci\u00f3n en su \u00a0territorio, o en su defecto, documento en el cual se especifiquen las razones \u00a0por las cuales no est\u00e1 autorizado, incluyendo: nombre del producto, f\u00f3rmula cualicuantitativa, forma farmac\u00e9utica, titular del registro \u00a0y nombre del fabricante. \u00a0 \u00a0<\/p>\n<p>8. Justificaci\u00f3n \u00a0epidemiol\u00f3gica y social de la donaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Los medicamentos \u00a0y dispositivos m\u00e9dicos recibidos en donaci\u00f3n al momento de ingresar al pa\u00eds, \u00a0deber\u00e1n contar con un sello o r\u00f3tulo en lugar visible con la leyenda \u00a0&#8220;Donaci\u00f3n, Prohibida su Venta&#8221; o similar, donde se especifique \u00a0claramente su car\u00e1cter no comercial. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 4\u00b0. Autorizaci\u00f3n \u00a0de donaciones. Los interesados en recibir una donaci\u00f3n de medicamentos y \u00a0dispositivos m\u00e9dicos deber\u00e1n solicitar autorizaci\u00f3n previa al Instituto \u00a0Nacional de Vigilancia de Medicamentos y Alimentos, Invima, \u00a0o de la entidad que haga sus veces. Para tal efecto, el interesado deber\u00e1 \u00a0diligenciar el formulario que establezca el Ministerio de la Protecci\u00f3n Social. \u00a0Una vez radicada la solicitud acompa\u00f1ada de la documentaci\u00f3n correspondiente al \u00a0art\u00edculo 3\u00ba del presente decreto, el Invima en un \u00a0plazo no mayor a cinco (5) d\u00edas autorizar\u00e1 o rechazar\u00e1 total o parcialmente la \u00a0donaci\u00f3n mediante acto administrativo. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Cuando el Invima lo considere pertinente, podr\u00e1 solicitar mediante \u00a0escrito ampliaci\u00f3n o aclaraci\u00f3n sobre la documentaci\u00f3n allegada. Para este \u00a0efecto, el interesado dispondr\u00e1 de un plazo no mayor de treinta 30 (d\u00edas) \u00a0calendario siguientes a la fecha de recibo de dicha comunicaci\u00f3n, al cabo de \u00a0los cuales, de no presentarse la informaci\u00f3n, se entender\u00e1 que el peticionario \u00a0desiste de la solicitud. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 5\u00b0. Verificaci\u00f3n \u00a0de la calidad y utilizaci\u00f3n de las donaciones. Cuando el Invima lo considere pertinente, podr\u00e1 verificar la calidad \u00a0de los medicamentos y dispositivos m\u00e9dicos cuya donaci\u00f3n haya sido autorizada. \u00a0Igualmente las Direcciones Departamentales o Distritales \u00a0de Salud en desarrollo de sus competencias de vigilancia y control, podr\u00e1n en \u00a0cualquier momento verificar la calidad y utilizaci\u00f3n de los medicamentos y \u00a0dispositivos m\u00e9dicos donados. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 6\u00b0. Vigilancia \u00a0y control. Para efectos de la vigilancia y control que deben ejercer las \u00a0direcciones departamentales y distritales de salud \u00a0sobre las donaciones, el Invima deber\u00e1 reportar \u00a0peri\u00f3dicamente, las autorizaciones que hayan sido otorgadas para ser utilizadas \u00a0en el respectivo territorio. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Cuando el \u00a0receptor desv\u00ede, se apropie, o haga mal uso de una donaci\u00f3n, el producto se \u00a0considerar\u00e1 fraudulento y en consecuencia ser\u00e1 sujeto de las sanciones \u00a0previstas en las normas sanitarias vigentes, en especial el Decreto 677 de 1995 \u00a0y dem\u00e1s normas que lo modifiquen, adicionen o sustituyan. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 7\u00b0. Prohibici\u00f3n \u00a0de comercializaci\u00f3n de donaciones. Los medicamentos y dispositivos m\u00e9dicos \u00a0que ingresen al pa\u00eds a trav\u00e9s de las donaciones de que trata el art\u00edculo 1\u00ba del \u00a0presente decreto, no podr\u00e1n ser comercializados ni utilizados con fines \u00a0lucrativos. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 8\u00b0. Vigencia. \u00a0El presente decreto rige a partir de la fecha de su publicaci\u00f3n, y modifica y \u00a0deroga las disposiciones que le sean contrarias. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 26 de marzo de 2004. \u00a0 \u00a0<\/p>\n<p>\u00c1LVARO URIBE V\u00c9LEZ \u00a0 \u00a0<\/p>\n<p>El Ministro de la \u00a0Protecci\u00f3n Social, \u00a0 \u00a0<\/p>\n<p>Diego Palacio Betancourt. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 919 DE 2004 \u00a0 \u00a0 (marzo 26) \u00a0 \u00a0 por el cual se reglamentan las donaciones internacionales de \u00a0medicamentos y dispositivos m\u00e9dicos. \u00a0 \u00a0 Nota 1: Derogado por el Decreto 218 de 2019, \u00a0art\u00edculo 15. \u00a0 \u00a0 Nota 2: Ver Decreto 2475 de 2018. \u00a0Ver Decreto 780 de 2016, \u00a0art\u00edculo 4.1.3, excluy\u00f3 de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-36283","post","type-post","status-publish","format-standard","hentry","category-decretos-2004"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/36283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=36283"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/36283\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=36283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=36283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=36283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}