{"id":40796,"date":"2023-07-28T17:08:06","date_gmt":"2023-07-28T17:08:06","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/28\/decreto-92-de-2008\/"},"modified":"2023-07-28T17:08:06","modified_gmt":"2023-07-28T17:08:06","slug":"decreto-92-de-2008","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/07\/28\/decreto-92-de-2008\/","title":{"rendered":"DECRETO 92 DE 2008"},"content":{"rendered":"\n<p>DECRETO 092 DE 2008 \u00a0 \u00a0<\/p>\n<p>(febrero 29) \u00a0 \u00a0<\/p>\n<p>por medio del cual se seleccionan los \u00a0proyectos de adecuaci\u00f3n de tierras de importancia estrat\u00e9gica que el Incoder \u00a0puede continuar ejecutando. \u00a0 \u00a0<\/p>\n<p>El Ministro de Agricultura y Desarrollo Rural, en ejercicio de las facultades \u00a0constitucionales y legales, en especial las conferidas en el numeral 20 del \u00a0art\u00edculo 21 de la Ley 1152 de 2007, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO \u00a0 \u00a0<\/p>\n<p>Que el numeral 20 del art\u00edculo 21 de la Ley 1152 de 2007 \u201cpor \u00a0la cual se dicta el Estatuto de Desarrollo Rural, se reforma el Instituto \u00a0Colombiano de Desarrollo Rural, Incoder, y se dictan otras disposiciones\u201d, \u00a0determin\u00f3 que son funciones del mencionado instituto: \u201cContinuar con la \u00a0titularidad de los contratos relacionados con dise\u00f1o y construcci\u00f3n de los \u00a0distritos de riego de importancia estrat\u00e9gica que el Gobierno Nacional \u00a0seleccione de aquellos que se encuentren pendientes de ejecuci\u00f3n en la \u00a0actualidad\u201d; \u00a0 \u00a0<\/p>\n<p>Que en virtud de esta facultad, el Gobierno Nacional debe proceder a \u00a0declarar los distritos de riego de importancia estrat\u00e9gica para que el Incoder \u00a0pueda continuar con su ejecuci\u00f3n; \u00a0 \u00a0<\/p>\n<p>Que el Instituto de Desarrollo Rural, Incoder, mediante documento de \u00a0fecha 8 de febrero de 2008, puso a consideraci\u00f3n del Gobierno Nacional once \u00a0(11) proyectos de adecuaci\u00f3n de tierras, para que a estos se les aplique el \u00a0numeral 20 del art\u00edculo 21 de la Ley 1152 de 2007; \u00a0 \u00a0<\/p>\n<p>Que como criterios de selecci\u00f3n se tienen las siguientes \u00a0consideraciones: Su contribuci\u00f3n al desarrollo regional y al aumento de la \u00a0generaci\u00f3n de ingresos para las familias beneficiarias. Su significativo \u00a0impacto en la productividad y competitividad agropecuaria en varias regiones \u00a0donde esta actividad econ\u00f3mica es predominante. La estabilidad econ\u00f3mica para \u00a0regiones con poblaci\u00f3n tradicionalmente agropecuaria. El desarrollo sostenible \u00a0en el mediano y corto plazo en la producci\u00f3n de alimentos. La optimizaci\u00f3n de \u00a0la escasa disponibilidad de agua y de los recursos naturales disponibles en \u00a0cada regi\u00f3n;Que en m\u00e9rito de lo expuesto, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Proyectos de importancia estrat\u00e9gica. El Incoder \u00a0podr\u00e1 continuar la ejecuci\u00f3n en materia de dise\u00f1o o construcci\u00f3n de los \u00a0siguientes distritos de riego de importancia estrat\u00e9gica, pendientes de \u00a0ejecuci\u00f3n en la actualidad: \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>Departamento \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Municipio \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Proyecto \u00a0\u00a0<\/p>\n<p>Antioquia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>San Isidro \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>T\u00e1mesis \u00a0\u00a0<\/p>\n<p>Atl\u00e1ntico \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Repel\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Repel\u00f3n \u00a0\u00a0<\/p>\n<p>Bol\u00edvar \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Mar\u00eda La Baja \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Mar\u00eda La Baja \u00a0\u00a0<\/p>\n<p>Cesar \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Tamalameque \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Buenos Aires \u00a0\u00a0<\/p>\n<p>C\u00f3rdoba \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Monter\u00eda \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Mocari \u00a0\u00a0<\/p>\n<p>C\u00f3rdoba \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Lorica \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>La Doctrina \u00a0\u00a0<\/p>\n<p>La Guajira \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Fonseca, San Juan del Cesar, Barranca y Distracci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Rancher\u00eda (todas sus \u00a0 \u00a0fases) \u00a0\u00a0<\/p>\n<p>Magdalena \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Zona Bananera \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Tucurinca \u00a0\u00a0<\/p>\n<p>Magdalena \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Aracataca \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Aracataca \u00a0\u00a0<\/p>\n<p>Norte de Santander \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Zulia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Zulia \u00a0\u00a0<\/p>\n<p>Tolima \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Coyaima, Natagaima y \u00a0 \u00a0Purificaci\u00f3n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Tri\u00e1ngulo (todas sus \u00a0 \u00a0fases) \u00a0 \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. Vigencia. \u00a0El presente decreto rige a partir de la fecha de su publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dada en Bogot\u00e1, D. C., \u00a0a 29 de febrero de 2008. \u00a0 \u00a0<\/p>\n<p>El Ministro de \u00a0Agricultura y Desarrollo Rural, \u00a0 \u00a0<\/p>\n<p>Andr\u00e9s Felipe \u00a0Arias Leiva. \u00a0 \u00a0<\/p>\n<p>(C.F.) \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 092 DE 2008 \u00a0 \u00a0 (febrero 29) \u00a0 \u00a0 por medio del cual se seleccionan los \u00a0proyectos de adecuaci\u00f3n de tierras de importancia estrat\u00e9gica que el Incoder \u00a0puede continuar ejecutando. \u00a0 \u00a0 El Ministro de Agricultura y Desarrollo Rural, en ejercicio de las facultades \u00a0constitucionales y legales, en especial las conferidas en el numeral [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63],"tags":[],"class_list":["post-40796","post","type-post","status-publish","format-standard","hentry","category-decretos-2008"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/40796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=40796"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/40796\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=40796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=40796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=40796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}